
{"id":896,"date":"2023-01-21T13:08:04","date_gmt":"2023-01-23T15:08:04","guid":{"rendered":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/congreso-futuro-2023-tuvo-exitoso-regreso-a-la-presencialidad\/"},"modified":"2023-01-23T12:09:42","modified_gmt":"2023-01-23T15:09:42","slug":"congreso-futuro-2023-tuvo-exitoso-regreso-a-la-presencialidad","status":"publish","type":"post","link":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/congreso-futuro-2023-tuvo-exitoso-regreso-a-la-presencialidad\/","title":{"rendered":"Congreso Futuro 2023 tuvo exitoso regreso a la presencialidad"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center text-right circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row][vc_column]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\"><span itemprop=\"name\">Vinculaci\u00f3n con el Medio<\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/noticias\/\"><span itemprop=\"name\">Noticias<\/span><\/a><meta itemprop=\"position\" content=\"3\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Congreso Futuro 2023 tuvo exitoso regreso a la presencialidad <\/span><meta itemprop=\"position\" content=\"4\" \/><\/ol><\/div><ul class=\"p-0 list-style-none d-inline-block\"><li class=\"p-0\"><a href=https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/category\/institucional\/ class=\"px-1 py-2\">Institucional<\/a><\/li><\/ul><div class=\"date_publish_post\"> \u25cf S\u00e1b 21 de Enero 2023<\/div><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block title--decorator  big\">Congreso Futuro 2023 tuvo exitoso regreso a la presencialidad<\/h1><\/div>[vc_row_inner el_class=&#8221;border-separator m-0&#8243;][vc_column_inner width=&#8221;2\/3&#8243;]<div class=\"author_wp_class\"> Escrito por <span>Universidad de O'Higgins<\/span><\/div>[\/vc_column_inner][vc_column_inner el_class=&#8221;align-items-end-publish&#8221; width=&#8221;1\/3&#8243;]<div class=\"uoh_social_network_component uoh_row col-12 justify-content-end m-0 p-0\"> <div class=\"icon__facebook-share-button\">\n                       <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/congreso-futuro-2023-tuvo-exitoso-regreso-a-la-presencialidad\/\" target=\"_blank\"> <div class=\"icon__facebook-svg\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22.4px\" height=\"48.3px\" viewBox=\"0 0 22.4 48.3\" style=\"overflow:visible;enable-background:new 0 0 22.4 48.3;\" xml:space=\"preserve\">\n                <defs>\n                <\/defs>\n                <path class=\"st0\" d=\"M22.4,15.6h-7.6v-5c0-1.9,1.2-2.3,2.1-2.3c0.9,0,5.4,0,5.4,0V0l-7.4,0C6.6,0,4.8,6.2,4.8,10.1v5.5H0v8.5h4.8\n                    c0,10.9,0,24.1,0,24.1h10c0,0,0-13.3,0-24.1h6.8L22.4,15.6z\"><\/path>\n                <\/svg><\/a><\/div>\n                    <\/div><div class=\"icon__twitter-share-button\">\n                        <div class=\"icon__twitter-svg\"><a target=\"_blank\" href=\"http:\/\/twitter.com\/share?url=https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/congreso-futuro-2023-tuvo-exitoso-regreso-a-la-presencialidad\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/a><\/div>\n                        <\/div><div class=\"icon__linkedin-share-button\">\n                        <div class=\"icon__linkedin-svg\">\n                        <a target=\"__blank\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/congreso-futuro-2023-tuvo-exitoso-regreso-a-la-presencialidad\/\"><svg enable-background=\"new 0 0 100 100\" height=\"100px\" id=\"Layer_1\" version=\"1.1\" viewBox=\"0 0 100 100\" width=\"100px\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><circle cx=\"50\" cy=\"50\" fill=\"#ccc\" r=\"45\"\/><g id=\"LinkedIn_1_\"><rect fill=\"#FFFFFF\" height=\"24.361\" width=\"7.69\" x=\"31.271\" y=\"43.569\"\/><path d=\"M59.968,43.334c-4.406,0-7.165,2.387-7.677,4.058v-3.823h-8.636c0.109,2.03,0,24.361,0,24.361h8.636    V54.748c0-0.733-0.034-1.465,0.19-1.991c0.594-1.464,1.869-2.985,4.162-2.985c2.998,0,4.361,2.253,4.361,5.552V67.93h8.721V54.384    C69.726,46.839,65.432,43.334,59.968,43.334z\" fill=\"#FFFFFF\"\/><path d=\"M34.973,32.069c-2.839,0-4.696,1.823-4.696,4.229c0,2.361,1.804,4.224,4.589,4.224h0.054    c2.891,0,4.69-1.869,4.69-4.229C39.555,33.888,37.81,32.069,34.973,32.069z\" fill=\"#FFFFFF\"\/><\/g><\/g><\/svg><\/a><\/div>\n\n            <\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_single_image image=&#8221;16687&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221;][vc_column_text]\u00a0[\/vc_column_text][vc_column_text]<\/p>\n<p id=\"m_-7866319283657237111m_-2997669952758923293gmail-E120\"><em><span id=\"m_-7866319283657237111m_-2997669952758923293gmail-E121\">Tras dos a\u00f1os de charlas v\u00eda remota, Congreso Futuro volvi\u00f3 a la presencialidad con \u00e9xito. M\u00e1s de 40 mil personas asistieron al Teatro Oriente en Santiago y a las diversas actividades que se realizaron en las 15 regiones del pa\u00eds. A su vez, m\u00e1s de 4 millones de usuarios se unieron de manera virtual.<\/span><\/em><\/p>\n<p>\u00a0[\/vc_column_text][vc_column_text]\u00a0[\/vc_column_text][vc_column_text]<\/p>\n<div id=\"m_-7866319283657237111m_-2997669952758923293gmail-contentsContainer\">\n<div id=\"m_-7866319283657237111m_-2997669952758923293gmail-contents\">\n<p id=\"m_-7866319283657237111m_-2997669952758923293gmail-E124\"><span id=\"m_-7866319283657237111m_-2997669952758923293gmail-E125\">Hablar de Congreso Futuro (CF) es hablar de un evento maduro y de importancia a nivel mundial, que tras 12 a\u00f1os de realizaci\u00f3n,\u00a0<\/span><span id=\"m_-7866319283657237111m_-2997669952758923293gmail-E126\">se ha convertido en un excelente panorama para el verano, donde todo el mundo es bienvenido y necesario.<\/span><\/p>\n<p id=\"m_-7866319283657237111m_-2997669952758923293gmail-E130\"><span id=\"m_-7866319283657237111m_-2997669952758923293gmail-E131\">\u201cLa \u00fanica forma en que realmente podemos crear un futuro inclusivo, es hacer todo lo posible por incluir a las personas que han sido marginadas\u201d, se\u00f1al\u00f3 en su presentaci\u00f3n la destacada educadora, oradora y activista transg\u00e9nero, Abby Stein, quien concit\u00f3 una de las mayores expectativas, entre los m\u00e1s de 120 expositores nacionales e internacionales que pasaron por el escenario del evento esta semana.<\/span><\/p>\n<p id=\"m_-7866319283657237111m_-2997669952758923293gmail-E134\"><span id=\"m_-7866319283657237111m_-2997669952758923293gmail-E135\">Este 2023 las conferencias estuvieron centradas en las tecnolog\u00edas y complejidades que conlleva el mundo del Metaverso, junto con sus desaf\u00edos y oportunidades. Tambi\u00e9n se abordaron tem\u00e1ticas relevantes para el futuro de la humanidad, como medioambiente, educaci\u00f3n y salud, todo bajo el eslogan #SinL\u00edmiteReal.<\/span><\/p>\n<p id=\"m_-7866319283657237111m_-2997669952758923293gmail-E138\"><span id=\"m_-7866319283657237111m_-2997669952758923293gmail-E139\">\u201cSin el Oc\u00e9ano la naturaleza no podr\u00eda existir, es el termorregulador del planeta, controla el clima, no existir\u00eda nada de lo que conocemos\u201d, se\u00f1al\u00f3 en su presentaci\u00f3n la bi\u00f3loga marina y activista estadounidense Sylvia Earle, quien a sus 87 a\u00f1os suma m\u00e1s de 100 expediciones y 7000 horas bajo el agua; Investigadora de gran experiencia que aplaudi\u00f3 al pa\u00eds por \u201csaber proteger los tesoros del planeta\u201d.<\/span><\/p>\n<p id=\"m_-7866319283657237111m_-2997669952758923293gmail-E142\"><span id=\"m_-7866319283657237111m_-2997669952758923293gmail-E143\">Congreso Futuro es un evento que nace en Chile, para sus territorios y el mundo. Con el objetivo de promover el conocimiento entre la sociedad nacional y exportarlo en una simbiosis de ideas que ayuden a proyectar un mejor futuro para todos y todas.<\/span><\/p>\n<p id=\"m_-7866319283657237111m_-2997669952758923293gmail-E146\"><span id=\"m_-7866319283657237111m_-2997669952758923293gmail-E147\">\u201cEstamos en una realidad amenazada por varios factores y para hacerle frente necesitamos juntarnos todos. El mundo privado con el mundo p\u00fablico, las regiones con el centro y la ciencia chilena con la mundial. CF es un espacio de encuentro \u00fanico para pensar los desaf\u00edos que tenemos como pa\u00eds en el futuro cercano. En esta era de la inmediatez necesitamos actualizar las ideas y pensamientos. A mayor tecnolog\u00eda m\u00e1s amenazas y necesitamos regularlas\u201d, se\u00f1al\u00f3 Guido Girardi, Vicepresidente de la Fundaci\u00f3n Encuentros del Futuro.<\/span><\/p>\n<p id=\"m_-7866319283657237111m_-2997669952758923293gmail-E151\"><span id=\"m_-7866319283657237111m_-2997669952758923293gmail-E152\">En el evento se discuten los desaf\u00edos del futuros que se determinan en el presente, como el complejo tema abordado por el fil\u00f3sofo y ling\u00fcista m\u00e1s reconocido de la historia moderna, Noam Chomsky, quien convers\u00f3 sobre las consecuencias de la crisis clim\u00e1tica y las posibles soluciones \u201cel carbono nos est\u00e1 afectando ampliamente y nos lleva a una destrucci\u00f3n\u00a0<\/span>incalculable. La ciencia nos ha demostrado que esto ya est\u00e1 sucediendo y prontamente estos sistemas van a ser irreversibles\u201d. Sin embargo, destac\u00f3 que hay una esperanza: \u201cHay buenas noticias y es la posibilidad de usar energ\u00edas renovables disponibles para construir un mundo mejor\u201d.<\/p>\n<\/div>\n<\/div>\n<div id=\"m_-7866319283657237111m_-2997669952758923293gmail-contentsContainer\">\n<div id=\"m_-7866319283657237111m_-2997669952758923293gmail-contents\">\n<p id=\"m_-7866319283657237111m_-2997669952758923293gmail-E155\"><span id=\"m_-7866319283657237111m_-2997669952758923293gmail-E156\">Esta y miles son las propuestas e ideas innovadoras que emergen durante la realizaci\u00f3n de la actividad organizada por la Comisi\u00f3n de Desaf\u00edos del Futuro y la Fundaci\u00f3n Encuentros del Futuro (FEF), quienes a partir del 2009 lideran Congreso Futuro junto a las Universidades del pa\u00eds, el Gobierno, la C\u00e1mara del Senado y de Diputados, instituciones privadas y la sociedad civil.<\/span><\/p>\n<h3 id=\"m_-7866319283657237111m_-2997669952758923293gmail-E159\"><span id=\"m_-7866319283657237111m_-2997669952758923293gmail-E160\">Congreso Futuro en regiones para el mundo<\/span><span id=\"m_-7866319283657237111m_-2997669952758923293gmail-E161\"><\/span><\/h3>\n<p id=\"m_-7866319283657237111m_-2997669952758923293gmail-E164\"><span id=\"m_-7866319283657237111m_-2997669952758923293gmail-E165\">Gracias al trabajo colaborativo de 50 universidades y centros de investigaci\u00f3n regionales p\u00fablicos y privados, el apoyo de los gobiernos regionales, CF reuni\u00f3 a m\u00e1s de 15 mil personas a lo largo y ancho del pa\u00eds, en locaciones como las Ruinas de Huanchaca, el Teatro B\u00edo B\u00edo, el Teatro Regional del Maule y el Sal\u00f3n de Honor del Congreso Nacional en Valpara\u00edso.<\/span><\/p>\n<p id=\"m_-7866319283657237111m_-2997669952758923293gmail-E168\"><span id=\"m_-7866319283657237111m_-2997669952758923293gmail-E169\">Fueron 34 charlistas internacionales los que se desplegaron entre Arica y Magallanes, realiz\u00e1ndose en 16 regiones, quienes junto a un centenar de expositores y expositoras locales, dieron vida a uno de los eventos cient\u00edficos, tecnol\u00f3gicos y culturales m\u00e1s importantes en Am\u00e9rica Latina.<\/span><\/p>\n<p id=\"m_-7866319283657237111m_-2997669952758923293gmail-E172\"><span id=\"m_-7866319283657237111m_-2997669952758923293gmail-E173\">Con tem\u00e1ticas como la ciberseguridad, el desarrollo de agricultura sustentable en base al calentamiento global, estudios de g\u00e9nero y diversidad, protecci\u00f3n y promoci\u00f3n de la vida marina, entre otros, las regiones marcaron la pauta con el desarrollo de este encuentro con divulgaci\u00f3n del conocimiento en diferentes t\u00f3picos. Con expositores como Abby Stein, Ekaterina Kostioukhina, Santiago Rinc\u00f3n Gallardo, Miguel Alcubierre, Anna Fores, Dyvia Chander, Sir Rattan Lal, entre otros.<\/span><\/p>\n<p id=\"m_-7866319283657237111m_-2997669952758923293gmail-E176\"><span id=\"m_-7866319283657237111m_-2997669952758923293gmail-E177\">\u201cCongreso Futuro se ha consolidado como un evento que logra generar pol\u00edticas p\u00fablicas de largo aliento, donde el foco es la democratizaci\u00f3n y el acceso a la ciencia, tecnolog\u00eda, innovaci\u00f3n y conocimiento. Este 2023 logramos desplegarnos de Arica a Magallanes con m\u00e1s de diez mil asistentes presenciales en todas las regiones, sin contar la Metropolitana. Tuvimos m\u00e1s de un mill\u00f3n de interacciones virtuales, por eso destacamos que este encuentro con la ciencia y el conocimiento ha sido capaz de consolidarse como tal, tanto as\u00ed que a partir de este 2023 seremos testigos de su internacionalizaci\u00f3n. Congreso Futuro se ha convertido en la posibilidad, a trav\u00e9s de las exposiciones y las interacciones entre acad\u00e9micos y cient\u00edficos, como un espacio donde se generan pol\u00edticas p\u00fablicas y legislaci\u00f3n para los nuevos desaf\u00edos que el futuro nos presenta\u201d se\u00f1al\u00f3 el senador Francisco Chahu\u00e1n, presidente de la Comisi\u00f3n de Desaf\u00edos Futuro.<br \/>\n<\/span><\/p>\n<h3 id=\"m_-7866319283657237111m_-2997669952758923293gmail-E180\"><span id=\"m_-7866319283657237111m_-2997669952758923293gmail-E181\"><b>Destacados CF Sin L\u00edmite Real<\/b><\/span><\/h3>\n<p>Entre las actividades m\u00e1s llamativas para las y los asistentes de la versi\u00f3n 2023, est\u00e1 el proyecto cient\u00edfico art\u00edstico que inaugur\u00f3 el evento, donde se revivi\u00f3 a la conciencia del destacado bi\u00f3logo Charles Darwin. Esto gracias a la implementaci\u00f3n de Inteligencia Artificial y el entrenamiento de algoritmos, quienes tras meses de trabajo fueron capaces de proyectar las respuestas que proporcionar\u00eda Darwin sobre problem\u00e1ticas de las sociedades actuales.<\/p>\n<\/div>\n<\/div>\n<div id=\"m_-7866319283657237111m_-2997669952758923293gmail-contentsContainer\">\n<div id=\"m_-7866319283657237111m_-2997669952758923293gmail-contents\">\n<p id=\"m_-7866319283657237111m_-2997669952758923293gmail-E188\"><span id=\"m_-7866319283657237111m_-2997669952758923293gmail-E189\">La campa\u00f1a que acompa\u00f1\u00f3 a Congreso Futuro fue uno de los puntos que destac\u00f3 p\u00fablicamente este mes, propuesta que mediante una alianza con Metro de Santiago, desarroll\u00f3 intervenciones art\u00edsticas y de conocimiento que se tomaron una de las principales redes de transporte p\u00fablico de Chile. Las estaciones Baquedano, Pedro de Valdivia, Los Leones y Tobalaba se vistieron de con la tem\u00e1tica de este a\u00f1o y los usuarios pudieron disfrutar de los \u201cM\u00f3dulos de experiencia Metaverso\u201d, donde pod\u00edan explorar el Metaverso con Oculus (lentes de realidad virtual). A su vez, 10.000 tarjetas Bip con la gr\u00e1fica de CF se pod\u00edan obtener en las boleter\u00edas y activar un mundo de realidad aumentada mediante un filtro de Instagram (<\/span><a id=\"m_-7866319283657237111m_-2997669952758923293gmail-E190\" href=\"https:\/\/www.instagram.com\/ar\/948190313231835\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.instagram.com\/ar\/948190313231835\/&amp;source=gmail&amp;ust=1674562877234000&amp;usg=AOvVaw25E939pMIyKESEFhXGdkY-\"><span id=\"m_-7866319283657237111m_-2997669952758923293gmail-E191\">https:\/\/www.instagram.com\/ar\/948190313231835\/<\/span><\/a><span id=\"m_-7866319283657237111m_-2997669952758923293gmail-E192\">\u00a0).<\/span><\/p>\n<p id=\"m_-7866319283657237111m_-2997669952758923293gmail-E195\"><span id=\"m_-7866319283657237111m_-2997669952758923293gmail-E196\">Todas las charlas nacionales y regionales, junto a cada uno de los temas abordados en el evento\u00a0<\/span><span id=\"m_-7866319283657237111m_-2997669952758923293gmail-E197\">est\u00e1n alojadas en el sitio\u00a0<\/span><a id=\"m_-7866319283657237111m_-2997669952758923293gmail-E198\" href=\"http:\/\/www.congresofuturo.cl\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.congresofuturo.cl\/&amp;source=gmail&amp;ust=1674562877234000&amp;usg=AOvVaw1htHVahHp22exDABdNxvgT\"><span id=\"m_-7866319283657237111m_-2997669952758923293gmail-E199\">www.congresofuturo.cl<\/span><\/a><span id=\"m_-7866319283657237111m_-2997669952758923293gmail-E200\">\u00a0para consultar de manera gratuita.<\/span><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650255686594{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center text-right p-md-0 pt-5 pb-5&#8243;][vc_column el_class=&#8221;pb-5&#8243;][vc_row_inner el_class=&#8221;pb-5&#8243;][vc_column_inner]<div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0\"><h2 class=\"title title--decorator title--ms d-inline-block\">Te Recomendamos<\/h2><\/div><\/div><div class=\"content-holder\"><div class=\"row  swipper-news-list not--activate-hack \"><div class=\"row -wrapper\"><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2026\/04\/Inauguracion-Ano-Academico-2026-6.jpg\" alt=\"Reflexi\u00f3n universitaria: UOH inaugura A\u00f1o Acad\u00e9mico 2026 pensando en los desaf\u00edos de la Educaci\u00f3n Superior\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Mi\u00e9rcoles 29, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/reflexion-universitaria-uoh-inaugura-ano-academico-2026-pensando-en-los-desafios-de-la-educacion-superior\/\">\n                                    <h3 class=\"small-space\">Reflexi\u00f3n universitaria: UOH inaugura A\u00f1o Acad\u00e9mico 2026 pensando en los desaf\u00edos de la Educaci\u00f3n Superior<\/h3><\/a>\n\n                                    <p>La ceremonia promovi\u00f3 el an\u00e1lisis acerca de los cambios educativos que se avecinan dentro de los procesos de formaci\u00f3n universitaria ajustados a contextos digitales.   <\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/reflexion-universitaria-uoh-inaugura-ano-academico-2026-pensando-en-los-desafios-de-la-educacion-superior\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/category\/cuech\/\">\n                                        CUECH<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2026\/04\/DSC_2431-scaled.jpg\" alt=\"Universidades estatales sellan hoja de ruta 2030: Red Desarrollo Sustentable entra en fase de consolidaci\u00f3n\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/1707;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Mi\u00e9rcoles 15, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/universidades-estatales-sellan-hoja-de-ruta-2030-red-desarrollo-sustentable-entra-en-fase-de-consolidacion\/\">\n                                    <h3 class=\"small-space\">Universidades estatales sellan hoja de ruta 2030: Red Desarrollo Sustentable entra en fase de consolidaci\u00f3n<\/h3><\/a>\n\n                                    <p>En el Plenario realizado en la Universidad de O'Higgins, los 18 planteles p\u00fablicos definieron sus metas estrat\u00e9gicas para el periodo 2026-2030. El plan priorizar\u00e1 la institucionalizaci\u00f3n de capacidades, un diplomado para organismos p\u00fablicos y la medici\u00f3n de la huella h\u00eddrica en los campus.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/universidades-estatales-sellan-hoja-de-ruta-2030-red-desarrollo-sustentable-entra-en-fase-de-consolidacion\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2026\/01\/IMG_6167-scaled.jpg\" alt=\"M\u00e1s di\u00e1logo y prevenci\u00f3n para consolidar un entorno de confianza\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/1707;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Lunes 19, Enero<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/mas-dialogo-y-prevencion-para-consolidar-un-entorno-de-confianza\/\">\n                                    <h3 class=\"small-space\">M\u00e1s di\u00e1logo y prevenci\u00f3n para consolidar un entorno de confianza<\/h3><\/a>\n\n                                    <p>La visita acad\u00e9mica permiti\u00f3 vincular los contenidos del curso Modelo de Desarrollo Regional con iniciativas reales de innovaci\u00f3n, sostenibilidad y articulaci\u00f3n p\u00fablico-privada impulsadas a nivel nacional.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/mas-dialogo-y-prevencion-para-consolidar-un-entorno-de-confianza\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pagination justify-content-center my-5\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/posts\/896\/\/page\/2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/posts\/896\/\/page\/3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/posts\/896\/\/page\/61\">61<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/posts\/896\/\/page\/2\"><div class=\"icon-pagination-next\"> <?xml version=\"1.0\" ?><svg viewBox=\"0 0 96 96\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><title\/><path d=\"M39.3756,48.0022l30.47-25.39a6.0035,6.0035,0,0,0-7.6878-9.223L26.1563,43.3906a6.0092,6.0092,0,0,0,0,9.2231L62.1578,82.615a6.0035,6.0035,0,0,0,7.6878-9.2231Z\"\/><\/svg> <\/div><\/a><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Tras dos a\u00f1os de charlas v\u00eda remota, Congreso Futuro volvi\u00f3 a la presencialidad con \u00e9xito. M\u00e1s de 40 mil personas asistieron al Teatro Oriente en Santiago y a las diversas actividades que se realizaron en las 15 regiones del pa\u00eds. A su vez, m\u00e1s de 4 millones de usuarios se unieron de manera virtual.<\/p>\n","protected":false},"author":34,"featured_media":899,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucional"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Congreso Futuro 2023 tuvo exitoso regreso a la presencialidad - Vinculaci\u00f3n con el Medio<\/title>\n<meta name=\"description\" content=\"Tras dos a\u00f1os de charlas v\u00eda remota, Congreso Futuro volvi\u00f3 a la presencialidad con \u00e9xito. M\u00e1s de 40 mil personas asistieron al Teatro Oriente en Santiago y a las diversas actividades que se realizaron en las 15 regiones del pa\u00eds. A su vez, m\u00e1s de 4 millones de usuarios se unieron de manera virtual.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Congreso Futuro 2023 tuvo exitoso regreso a la presencialidad - Vinculaci\u00f3n con el Medio\" \/>\n<meta property=\"og:description\" content=\"Tras dos a\u00f1os de charlas v\u00eda remota, Congreso Futuro volvi\u00f3 a la presencialidad con \u00e9xito. M\u00e1s de 40 mil personas asistieron al Teatro Oriente en Santiago y a las diversas actividades que se realizaron en las 15 regiones del pa\u00eds. A su vez, m\u00e1s de 4 millones de usuarios se unieron de manera virtual.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/congreso-futuro-2023-tuvo-exitoso-regreso-a-la-presencialidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Vinculaci\u00f3n con el Medio\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-23T15:08:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-23T15:09:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2023\/01\/Congreso-Futuro-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Universidad de O&#039;Higgins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Universidad de O&#039;Higgins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/congreso-futuro-2023-tuvo-exitoso-regreso-a-la-presencialidad\/\",\"url\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/congreso-futuro-2023-tuvo-exitoso-regreso-a-la-presencialidad\/\",\"name\":\"Congreso Futuro 2023 tuvo exitoso regreso a la presencialidad - Vinculaci\u00f3n con el Medio\",\"isPartOf\":{\"@id\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/congreso-futuro-2023-tuvo-exitoso-regreso-a-la-presencialidad\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/congreso-futuro-2023-tuvo-exitoso-regreso-a-la-presencialidad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2023\/01\/Congreso-Futuro-2.jpg\",\"datePublished\":\"2023-01-23T15:08:04+00:00\",\"dateModified\":\"2023-01-23T15:09:42+00:00\",\"author\":{\"@id\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"description\":\"Tras dos a\u00f1os de charlas v\u00eda remota, Congreso Futuro volvi\u00f3 a la presencialidad con \u00e9xito. M\u00e1s de 40 mil personas asistieron al Teatro Oriente en Santiago y a las diversas actividades que se realizaron en las 15 regiones del pa\u00eds. A su vez, m\u00e1s de 4 millones de usuarios se unieron de manera virtual.\",\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/congreso-futuro-2023-tuvo-exitoso-regreso-a-la-presencialidad\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/congreso-futuro-2023-tuvo-exitoso-regreso-a-la-presencialidad\/#primaryimage\",\"url\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2023\/01\/Congreso-Futuro-2.jpg\",\"contentUrl\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2023\/01\/Congreso-Futuro-2.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#website\",\"url\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/\",\"name\":\"Vinculaci\u00f3n con el Medio\",\"description\":\"Otro sitio de Sitios de Universidad O&#039;higgins\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\",\"name\":\"Universidad de O'Higgins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"caption\":\"Universidad de O'Higgins\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Congreso Futuro 2023 tuvo exitoso regreso a la presencialidad - Vinculaci\u00f3n con el Medio","description":"Tras dos a\u00f1os de charlas v\u00eda remota, Congreso Futuro volvi\u00f3 a la presencialidad con \u00e9xito. M\u00e1s de 40 mil personas asistieron al Teatro Oriente en Santiago y a las diversas actividades que se realizaron en las 15 regiones del pa\u00eds. A su vez, m\u00e1s de 4 millones de usuarios se unieron de manera virtual.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Congreso Futuro 2023 tuvo exitoso regreso a la presencialidad - Vinculaci\u00f3n con el Medio","og_description":"Tras dos a\u00f1os de charlas v\u00eda remota, Congreso Futuro volvi\u00f3 a la presencialidad con \u00e9xito. M\u00e1s de 40 mil personas asistieron al Teatro Oriente en Santiago y a las diversas actividades que se realizaron en las 15 regiones del pa\u00eds. A su vez, m\u00e1s de 4 millones de usuarios se unieron de manera virtual.","og_url":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/congreso-futuro-2023-tuvo-exitoso-regreso-a-la-presencialidad\/","og_site_name":"Vinculaci\u00f3n con el Medio","article_published_time":"2023-01-23T15:08:04+00:00","article_modified_time":"2023-01-23T15:09:42+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2023\/01\/Congreso-Futuro-2.jpg","type":"image\/jpeg"}],"author":"Universidad de O'Higgins","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Universidad de O'Higgins","Tiempo estimado de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/congreso-futuro-2023-tuvo-exitoso-regreso-a-la-presencialidad\/","url":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/congreso-futuro-2023-tuvo-exitoso-regreso-a-la-presencialidad\/","name":"Congreso Futuro 2023 tuvo exitoso regreso a la presencialidad - Vinculaci\u00f3n con el Medio","isPartOf":{"@id":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/congreso-futuro-2023-tuvo-exitoso-regreso-a-la-presencialidad\/#primaryimage"},"image":{"@id":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/congreso-futuro-2023-tuvo-exitoso-regreso-a-la-presencialidad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2023\/01\/Congreso-Futuro-2.jpg","datePublished":"2023-01-23T15:08:04+00:00","dateModified":"2023-01-23T15:09:42+00:00","author":{"@id":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"description":"Tras dos a\u00f1os de charlas v\u00eda remota, Congreso Futuro volvi\u00f3 a la presencialidad con \u00e9xito. M\u00e1s de 40 mil personas asistieron al Teatro Oriente en Santiago y a las diversas actividades que se realizaron en las 15 regiones del pa\u00eds. A su vez, m\u00e1s de 4 millones de usuarios se unieron de manera virtual.","inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/congreso-futuro-2023-tuvo-exitoso-regreso-a-la-presencialidad\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/congreso-futuro-2023-tuvo-exitoso-regreso-a-la-presencialidad\/#primaryimage","url":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2023\/01\/Congreso-Futuro-2.jpg","contentUrl":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2023\/01\/Congreso-Futuro-2.jpg","width":1000,"height":1000},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#website","url":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/","name":"Vinculaci\u00f3n con el Medio","description":"Otro sitio de Sitios de Universidad O&#039;higgins","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f","name":"Universidad de O'Higgins","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","caption":"Universidad de O'Higgins"}}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/posts\/896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/comments?post=896"}],"version-history":[{"count":1,"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/posts\/896\/revisions"}],"predecessor-version":[{"id":898,"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/posts\/896\/revisions\/898"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/media\/899"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/media?parent=896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/categories?post=896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/tags?post=896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}