
{"id":1075,"date":"2023-12-06T14:53:50","date_gmt":"2023-12-06T17:53:50","guid":{"rendered":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/preparate-congreso-futuro-2024-desde-chile-en-todas-las-regiones-y-para-todo-el-mundo\/"},"modified":"2023-12-07T10:31:58","modified_gmt":"2023-12-07T13:31:58","slug":"preparate-congreso-futuro-2024-desde-chile-en-todas-las-regiones-y-para-todo-el-mundo","status":"publish","type":"post","link":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/preparate-congreso-futuro-2024-desde-chile-en-todas-las-regiones-y-para-todo-el-mundo\/","title":{"rendered":"\u00a1Prep\u00e1rate! Congreso Futuro 2024 desde Chile, en todas las regiones y para todo el mundo"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row][vc_column]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\"><span itemprop=\"name\">Vinculaci\u00f3n con el Medio<\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/noticias\/\"><span itemprop=\"name\">Noticias<\/span><\/a><meta itemprop=\"position\" content=\"3\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">\u00a1Prep\u00e1rate! Congreso Futuro 2024 desde Chile, en todas las regiones <\/span><meta itemprop=\"position\" content=\"4\" \/><\/ol><\/div><ul class=\"p-0 list-style-none d-inline-block\"><li class=\"p-0\"><a href=https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/category\/institucional\/ class=\"px-1 py-2\">Institucional<\/a><\/li><\/ul><div class=\"date_publish_post\"> \u25cf Mi\u00e9 06 de Diciembre 2023<\/div><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block title--decorator  big\">\u00a1Prep\u00e1rate! Congreso Futuro 2024 desde Chile, en todas las regiones y para todo el mundo<\/h1><\/div>[vc_row_inner el_class=&#8221;border-separator m-0&#8243;][vc_column_inner width=&#8221;2\/3&#8243;]<div class=\"author_wp_class\"> Escrito por <span>Universidad de O'Higgins<\/span><\/div>[\/vc_column_inner][vc_column_inner el_class=&#8221;align-items-end-publish&#8221; width=&#8221;1\/3&#8243;]<div class=\"uoh_social_network_component uoh_row col-12 justify-content-end m-0 p-0\"> <div class=\"icon__facebook-share-button\">\n                       <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/preparate-congreso-futuro-2024-desde-chile-en-todas-las-regiones-y-para-todo-el-mundo\/\" target=\"_blank\"> <div class=\"icon__facebook-svg\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22.4px\" height=\"48.3px\" viewBox=\"0 0 22.4 48.3\" style=\"overflow:visible;enable-background:new 0 0 22.4 48.3;\" xml:space=\"preserve\">\n                <defs>\n                <\/defs>\n                <path class=\"st0\" d=\"M22.4,15.6h-7.6v-5c0-1.9,1.2-2.3,2.1-2.3c0.9,0,5.4,0,5.4,0V0l-7.4,0C6.6,0,4.8,6.2,4.8,10.1v5.5H0v8.5h4.8\n                    c0,10.9,0,24.1,0,24.1h10c0,0,0-13.3,0-24.1h6.8L22.4,15.6z\"><\/path>\n                <\/svg><\/a><\/div>\n                    <\/div><div class=\"icon__twitter-share-button\">\n                        <div class=\"icon__twitter-svg\"><a target=\"_blank\" href=\"http:\/\/twitter.com\/share?url=https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/preparate-congreso-futuro-2024-desde-chile-en-todas-las-regiones-y-para-todo-el-mundo\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/a><\/div>\n                        <\/div><div class=\"icon__linkedin-share-button\">\n                        <div class=\"icon__linkedin-svg\">\n                        <a target=\"__blank\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/preparate-congreso-futuro-2024-desde-chile-en-todas-las-regiones-y-para-todo-el-mundo\/\"><svg enable-background=\"new 0 0 100 100\" height=\"100px\" id=\"Layer_1\" version=\"1.1\" viewBox=\"0 0 100 100\" width=\"100px\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><circle cx=\"50\" cy=\"50\" fill=\"#ccc\" r=\"45\"\/><g id=\"LinkedIn_1_\"><rect fill=\"#FFFFFF\" height=\"24.361\" width=\"7.69\" x=\"31.271\" y=\"43.569\"\/><path d=\"M59.968,43.334c-4.406,0-7.165,2.387-7.677,4.058v-3.823h-8.636c0.109,2.03,0,24.361,0,24.361h8.636    V54.748c0-0.733-0.034-1.465,0.19-1.991c0.594-1.464,1.869-2.985,4.162-2.985c2.998,0,4.361,2.253,4.361,5.552V67.93h8.721V54.384    C69.726,46.839,65.432,43.334,59.968,43.334z\" fill=\"#FFFFFF\"\/><path d=\"M34.973,32.069c-2.839,0-4.696,1.823-4.696,4.229c0,2.361,1.804,4.224,4.589,4.224h0.054    c2.891,0,4.69-1.869,4.69-4.229C39.555,33.888,37.81,32.069,34.973,32.069z\" fill=\"#FFFFFF\"\/><\/g><\/g><\/svg><\/a><\/div>\n\n            <\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_single_image image=&#8221;29762&#8243; img_size=&#8221;full&#8221; add_caption=&#8221;yes&#8221; alignment=&#8221;center&#8221; onclick=&#8221;img_link_large&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]\u00a0[\/vc_column_text][vc_column_text]<\/p>\n<ul>\n<li><em>\u00a1Ciencia, tecnolog\u00eda, humanidades, arte e innovaci\u00f3n para todo Chile!<\/em><\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_column_text]\u00a0[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"font-weight: 400\">Por segundo a\u00f1o consecutivo,\u00a0Congreso Futuro\u00a0se desplegar\u00e1 \u2013del 15 al 20 de enero\u2013 por\u00a0todas las regiones de Chile, desde Arica y Parinacota hasta Magallanes y la Ant\u00e1rtica chilena, permitiendo que los territorios puedan conocer y reflexionar sobre los futuros posibles que les afectan localmente y logren encontrar una respuesta a la pregunta que nos plantea esta versi\u00f3n 13&#8230; <em>\u00bfIAHORA QU\u00c9 HACEMOS?<\/em><\/p>\n<p style=\"font-weight: 400\">M\u00e1s de 40 expositores internacionales y 100 nacionales ser\u00e1n parte de Congreso Futuro Regiones, encuentros locales realizados por el\u00a0Senado, a trav\u00e9s de la Comisi\u00f3n Desaf\u00edos del Futuro\u00a0(presidida por la senadora\u00a0Ximena Rinc\u00f3n\u00a0e integrada por la legisladora\u00a0Ximena \u00d3rdenes\u00a0y los senadores\u00a0Francisco Chahu\u00e1n, Alfonso De Urresti y Felipe Kast),\u00a0\u00a0y la\u00a0Fundaci\u00f3n Encuentros del Futuro, a cargo de su vicepresidente ejecutivo,\u00a0Guido Girardi, entidades que trabajan en conjunto con\u00a0universidades locales, centros de investigaci\u00f3n e instituciones p\u00fablicas.<\/p>\n<p style=\"font-weight: 400\">La\u00a0presidenta de la Comisi\u00f3n Desaf\u00edos del Futuro y representante de la regi\u00f3n del Maule, senadora Ximena Rinc\u00f3n,\u00a0se\u00f1al\u00f3 que \u201cCongreso Futuro Regiones\u00a0es importante por lo que significa que todo el territorio de nuestro pa\u00eds puede expresarse, mostrar su potencialidad, su conocimiento, los aportes que -desde las regiones- hacemos al desarrollo, y a so\u00f1ar y pensar en nuestro pa\u00eds y su futuro\u201d.<\/p>\n<p style=\"font-weight: 400\">En la misma l\u00ednea, el\u00a0vicepresidente ejecutivo de la Fundaci\u00f3n Encuentros del Futuro (FEF),\u00a0Guido Girardi, se\u00f1al\u00f3 que \u201clos territorios son oportunidades para Chile y pueden salvar al planeta (\u2026) Tenemos los mayores potenciales del mundo; en astronom\u00eda, en oc\u00e9anos, para llevar vida al universo con seres vivos extrem\u00f3filos del \u00a0desierto de Atacama y la Ant\u00e1rtica con las principales reservas de agua. Hablar de Chile es hablar de sus territorios\u201d.<\/p>\n<p style=\"font-weight: 400\">Es por ello que para este 2024, las regiones han enfocado sus esfuerzos en abordar\u00a0tem\u00e1ticas que impactan directamente a sus territorios y comunidad. Dependiendo de la regi\u00f3n, los contenidos tratar\u00e1n:\u00a0<em>educaci\u00f3n en la era digital, supercomputadores y manejo de Big Data, paleontolog\u00eda, cambio clim\u00e1tico, soluciones basadas en IA sobre agua, Ciberseguridad Gen\u00e9tica, biotecnolog\u00eda, dise\u00f1o de f\u00e1rmacos, \u00e9tica de la IA y contaminaci\u00f3n del oc\u00e9ano por pl\u00e1sticos,<\/em>\u00a0entre otros.<\/p>\n<h4 style=\"font-weight: 400\"><strong>Fechas CG2024 en regiones<\/strong><\/h4>\n<p style=\"font-weight: 400\">Ser\u00e1n 16 regiones (incluyendo la Metropolitana) las que -del\u00a015 al 20 de enero- tendr\u00e1n una vinculaci\u00f3n especial en todo el territorio nacional.\u00a0Congreso Futuro\u00a0realizar\u00e1 su versi\u00f3n local\u00a0desde Arica y Parinacota hasta Magallanes y la Ant\u00e1rtica chilena\u00a0para reflexionar bajo el slogan\u00a0\u00bfIAHORA QU\u00c9 HACEMOS?\u00a0y as\u00ed conocer los futuros posibles que nos afectan como ciudadan\u00eda dependiendo del lugar en el que estemos.<\/p>\n<p style=\"font-weight: 400\">El recorrido comenzar\u00e1 el\u00a015 de enero en Magallanes, as\u00ed lo anunci\u00f3\u00a0el rector de la Universidad de Magallanes, Jos\u00e9 Maripani,\u00a0quien manifest\u00f3 que \u201cesta iniciativa ayuda a imaginar el futuro de nuestras regiones, permite buscar soluciones a sus problemas y conocer finalmente el gran laboratorio natural que tenemos en cada una de ellas. En Magallanes, decimos que este es el gran laboratorio natural abierto que act\u00faa como centinela de los cambios clim\u00e1ticos globales\u201d.<\/p>\n<p style=\"font-weight: 400\">Es de gran importancia para el Senado y los integrantes de la\u00a0Comisi\u00f3n Desaf\u00edos del Futuro, descentralizar\u00a0Congreso Futuro\u00a0a los territorios, as\u00ed lo manifest\u00f3 la\u00a0senadora por Ays\u00e9n, Ximena \u00d3rdenes,\u00a0quien indic\u00f3\u00a0que \u201ces una se\u00f1al potente de descentralizaci\u00f3n (\u2026) Ofrece un espacio donde confluyen investigadores que desde su rol abordan temas asociados a los desaf\u00edos locales que se proponen desde los propios territorios\u201d.<\/p>\n<p style=\"font-weight: 400\">Para el\u00a0senador de la regi\u00f3n de Valpara\u00edso, Francisco Chahu\u00e1n\u00a0\u201cesta descentralizaci\u00f3n a todo Chile representa un paso definitivo para consolidar un eje que permita generar masa cr\u00edtica en las regiones\u201d, mientras que para el\u00a0senador de la regi\u00f3n de Los R\u00edos, Alfonso De Urresti,\u00a0 \u201cla llegada a los territorios de\u00a0Congreso Futuro Regiones hay que consolidarla y expandirla con el fin de generar una estrecha\u00a0vinculaci\u00f3n con las universidades regionales, los centros de investigaci\u00f3n y la comunidad educativa\u201d.<\/p>\n<p style=\"font-weight: 400\">Donde quiera que est\u00e9s agenda tu fecha:<\/p>\n<ul>\n<li style=\"font-weight: 400\"><u>Lunes 15 enero<\/u>:<\/li>\n<\/ul>\n<p style=\"font-weight: 400\">\u00a0 \u00a0 \u00a0Magallanes \/\u00a0Lugar: CADI &#8211; UMAG de la Universidad de\u00a0Magallanes (Punta Arenas).<\/p>\n<ul>\n<li style=\"font-weight: 400\"><u><\/u><u>Martes 16 enero<\/u>:<\/li>\n<\/ul>\n<p style=\"font-weight: 400\">\u00a0 \u00a0 \u00a0Arica y Parinacota \/\u00a0Lugar: Auditorio Medicina Universidad de\u00a0Tarapac\u00e1 \u00a0(Av. Senador Luis Valente Rossi -2223 \/ Arica).<\/p>\n<p style=\"font-weight: 400\">\u00a0 \u00a0 \u00a0Tarapac\u00e1 \/\u00a0Lugar: Aula Magna Universidad Arturo Prat. (Avda\u00a0Arturo Prat 2120 \/ Iquique).<\/p>\n<p style=\"font-weight: 400\">\u00a0 \u00a0 \u00a0Atacama \/\u00a0Lugar: Centro Cultural Atacama (Copiap\u00f3).<\/p>\n<p style=\"font-weight: 400\">\u00a0 \u00a0 \u00a0Valpara\u00edso \/\u00a0Lugar: Sal\u00f3n de Honor Congreso Nacional\u00a0(Pedro Montt s\/n \/ Valpara\u00edso).<\/p>\n<p style=\"font-weight: 400\">\u00a0 \u00a0 \u00a0B\u00edo B\u00edo \/\u00a0Lugar: Teatro Universidad de Concepci\u00f3n (Av. Bernardo\u00a0O\u00b4Higgins 660 \/ Concepci\u00f3n).<\/p>\n<p style=\"font-weight: 400\">\u00a0 \u00a0 \u00a0Araucan\u00eda \/ Teatro Municipal de Temuco (Av. Pablo Neruda #01380 \/Temuco)<\/p>\n<ul>\n<li style=\"font-weight: 400\"><u>Mi\u00e9rcoles 17 en<\/u><u>ero:<\/u><\/li>\n<\/ul>\n<p style=\"font-weight: 400\">\u00a0 \u00a0 \u00a0Antofagasta \/ POR CONFIRMAR<\/p>\n<p style=\"font-weight: 400\">\u00a0 \u00a0 Coquimbo \/\u00a0Lugar:\u00a0Sal\u00f3n de la Gobernaci\u00f3n (Frente a la Plaza de\u00a0Armas de La Serena).<\/p>\n<p style=\"font-weight: 400\">\u00a0 \u00a0 \u00d1uble \/\u00a0Lugar: Teatro Municipal de Chill\u00e1n (Dieciocho de Septiembre 590 \/ Chill\u00e1n).<\/p>\n<p style=\"font-weight: 400\">\u00a0 \u00a0 Los Lagos \/\u00a0Lugar: Campus Puerto Montt, Universidad de Los\u00a0Lagos (Avenida Ega\u00f1a 1151 \/ Puerto Montt).<\/p>\n<ul>\n<li style=\"font-weight: 400\"><u>Jueves 18 enero:\u00a0<\/u><\/li>\n<\/ul>\n<p style=\"font-weight: 400\">\u00a0 \u00a0 O\u2019Higgins \/\u00a0Lugar: Auditorio Universidad de\u00a0O&#8217;Higgins\u00a0Rancagua (Av Libertador Bernardo O&#8217;Higgins 390 \/ Rancagua).<\/p>\n<p style=\"font-weight: 400\">\u00a0 \u00a0 Maule\/\u00a0Lugar: Teatro Regional del Maule (Calle uno oriente 1484 \/ Talca).<\/p>\n<ul>\n<li style=\"font-weight: 400\"><u>Viernes 19 enero:<\/u><\/li>\n<\/ul>\n<p style=\"font-weight: 400\">\u00a0 \u00a0 Los R\u00edos\u00a0\/\u00a0 Lugar: Aula Magna Universidad Austral de Chile\u00a0(Campus Isla Teja s\/n \/ Valdivia).<\/p>\n<p style=\"font-weight: 400\">\u00a0 \u00a0\u00a0Ays\u00e9n\u00a0\/ Lugar: Centro Cultural de Coyhaique (Eusebio Lillo 23 \/ Coyhaique).<\/p>\n<ul>\n<li style=\"font-weight: 400\"><u>\u00a0<\/u><u>Del 15 al 20 de enero: \u00a0<\/u><\/li>\n<\/ul>\n<p style=\"font-weight: 400\">\u00a0 \u00a0 \u00a0 Metropolitana\u00a0\/ Lugar: \u00a0Centro Cultural CEINA (Arturo Prat #33,\u00a0\/ Santiago Centro).<\/p>\n<p style=\"font-weight: 400\">Ya est\u00e1 todo listo. El\u00a0programa de Congreso Futuro Regiones\u00a0estar\u00e1 disponible en el sitio web\u00a0<u><a href=\"https:\/\/congresofuturo.cl\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/congresofuturo.cl\/&amp;source=gmail&amp;ust=1701963965030000&amp;usg=AOvVaw07wKyTy9T3ZGuSz5RKg0FT\">https:\/\/congresofuturo.cl\/<\/a><\/u>\u00a0a partir de\u00a0diciembre.<\/p>\n<p style=\"font-weight: 400\">S\u00famate a vivir esta experiencia de\u00a0Congreso Futuro Regiones 2024.<\/p>\n<p>[\/vc_column_text][vc_zigzag color=&#8221;white&#8221;][vc_row_inner][vc_column_inner][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650255686594{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center p-md-0 pt-5 pb-5&#8243;][vc_column el_class=&#8221;pb-5&#8243;][vc_row_inner el_class=&#8221;pb-5&#8243;][vc_column_inner]<div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0\"><h2 class=\"title title--decorator title--ms d-inline-block\">Te Recomendamos<\/h2><\/div><\/div><div class=\"content-holder\"><div class=\"row  swipper-news-list not--activate-hack \"><div class=\"row -wrapper\"><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2026\/04\/Inauguracion-Ano-Academico-2026-6.jpg\" alt=\"Reflexi\u00f3n universitaria: UOH inaugura A\u00f1o Acad\u00e9mico 2026 pensando en los desaf\u00edos de la Educaci\u00f3n Superior\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Mi\u00e9rcoles 29, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/reflexion-universitaria-uoh-inaugura-ano-academico-2026-pensando-en-los-desafios-de-la-educacion-superior\/\">\n                                    <h3 class=\"small-space\">Reflexi\u00f3n universitaria: UOH inaugura A\u00f1o Acad\u00e9mico 2026 pensando en los desaf\u00edos de la Educaci\u00f3n Superior<\/h3><\/a>\n\n                                    <p>La ceremonia promovi\u00f3 el an\u00e1lisis acerca de los cambios educativos que se avecinan dentro de los procesos de formaci\u00f3n universitaria ajustados a contextos digitales.   <\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/reflexion-universitaria-uoh-inaugura-ano-academico-2026-pensando-en-los-desafios-de-la-educacion-superior\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/category\/cuech\/\">\n                                        CUECH<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2026\/04\/DSC_2431-scaled.jpg\" alt=\"Universidades estatales sellan hoja de ruta 2030: Red Desarrollo Sustentable entra en fase de consolidaci\u00f3n\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/1707;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Mi\u00e9rcoles 15, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/universidades-estatales-sellan-hoja-de-ruta-2030-red-desarrollo-sustentable-entra-en-fase-de-consolidacion\/\">\n                                    <h3 class=\"small-space\">Universidades estatales sellan hoja de ruta 2030: Red Desarrollo Sustentable entra en fase de consolidaci\u00f3n<\/h3><\/a>\n\n                                    <p>En el Plenario realizado en la Universidad de O'Higgins, los 18 planteles p\u00fablicos definieron sus metas estrat\u00e9gicas para el periodo 2026-2030. El plan priorizar\u00e1 la institucionalizaci\u00f3n de capacidades, un diplomado para organismos p\u00fablicos y la medici\u00f3n de la huella h\u00eddrica en los campus.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/universidades-estatales-sellan-hoja-de-ruta-2030-red-desarrollo-sustentable-entra-en-fase-de-consolidacion\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2026\/01\/IMG_6167-scaled.jpg\" alt=\"M\u00e1s di\u00e1logo y prevenci\u00f3n para consolidar un entorno de confianza\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/1707;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Lunes 19, Enero<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/mas-dialogo-y-prevencion-para-consolidar-un-entorno-de-confianza\/\">\n                                    <h3 class=\"small-space\">M\u00e1s di\u00e1logo y prevenci\u00f3n para consolidar un entorno de confianza<\/h3><\/a>\n\n                                    <p>La visita acad\u00e9mica permiti\u00f3 vincular los contenidos del curso Modelo de Desarrollo Regional con iniciativas reales de innovaci\u00f3n, sostenibilidad y articulaci\u00f3n p\u00fablico-privada impulsadas a nivel nacional.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/mas-dialogo-y-prevencion-para-consolidar-un-entorno-de-confianza\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pagination justify-content-center my-5\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/posts\/1075\/\/page\/2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/posts\/1075\/\/page\/3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/posts\/1075\/\/page\/61\">61<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/posts\/1075\/\/page\/2\"><div class=\"icon-pagination-next\"> <?xml version=\"1.0\" ?><svg viewBox=\"0 0 96 96\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><title\/><path d=\"M39.3756,48.0022l30.47-25.39a6.0035,6.0035,0,0,0-7.6878-9.223L26.1563,43.3906a6.0092,6.0092,0,0,0,0,9.2231L62.1578,82.615a6.0035,6.0035,0,0,0,7.6878-9.2231Z\"\/><\/svg> <\/div><\/a><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u00a1Ciencia, tecnolog\u00eda, humanidades, arte e innovaci\u00f3n para todo Chile!<\/p>\n","protected":false},"author":34,"featured_media":1078,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-1075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucional"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00a1Prep\u00e1rate! Congreso Futuro 2024 desde Chile, en todas las regiones y para todo el mundo - Vinculaci\u00f3n con el Medio<\/title>\n<meta name=\"description\" content=\"\u00a1Ciencia, tecnolog\u00eda, humanidades, arte e innovaci\u00f3n para todo Chile!\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Prep\u00e1rate! Congreso Futuro 2024 desde Chile, en todas las regiones y para todo el mundo - Vinculaci\u00f3n con el Medio\" \/>\n<meta property=\"og:description\" content=\"\u00a1Ciencia, tecnolog\u00eda, humanidades, arte e innovaci\u00f3n para todo Chile!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/preparate-congreso-futuro-2024-desde-chile-en-todas-las-regiones-y-para-todo-el-mundo\/\" \/>\n<meta property=\"og:site_name\" content=\"Vinculaci\u00f3n con el Medio\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-06T17:53:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-07T13:31:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2023\/12\/Congreso-Futuro-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Universidad de O&#039;Higgins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Universidad de O&#039;Higgins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/preparate-congreso-futuro-2024-desde-chile-en-todas-las-regiones-y-para-todo-el-mundo\/\",\"url\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/preparate-congreso-futuro-2024-desde-chile-en-todas-las-regiones-y-para-todo-el-mundo\/\",\"name\":\"\u00a1Prep\u00e1rate! Congreso Futuro 2024 desde Chile, en todas las regiones y para todo el mundo - Vinculaci\u00f3n con el Medio\",\"isPartOf\":{\"@id\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/preparate-congreso-futuro-2024-desde-chile-en-todas-las-regiones-y-para-todo-el-mundo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/preparate-congreso-futuro-2024-desde-chile-en-todas-las-regiones-y-para-todo-el-mundo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2023\/12\/Congreso-Futuro-2.png\",\"datePublished\":\"2023-12-06T17:53:50+00:00\",\"dateModified\":\"2023-12-07T13:31:58+00:00\",\"author\":{\"@id\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"description\":\"\u00a1Ciencia, tecnolog\u00eda, humanidades, arte e innovaci\u00f3n para todo Chile!\",\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/preparate-congreso-futuro-2024-desde-chile-en-todas-las-regiones-y-para-todo-el-mundo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/preparate-congreso-futuro-2024-desde-chile-en-todas-las-regiones-y-para-todo-el-mundo\/#primaryimage\",\"url\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2023\/12\/Congreso-Futuro-2.png\",\"contentUrl\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2023\/12\/Congreso-Futuro-2.png\",\"width\":1000,\"height\":1000},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#website\",\"url\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/\",\"name\":\"Vinculaci\u00f3n con el Medio\",\"description\":\"Otro sitio de Sitios de Universidad O&#039;higgins\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\",\"name\":\"Universidad de O'Higgins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"caption\":\"Universidad de O'Higgins\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Prep\u00e1rate! Congreso Futuro 2024 desde Chile, en todas las regiones y para todo el mundo - Vinculaci\u00f3n con el Medio","description":"\u00a1Ciencia, tecnolog\u00eda, humanidades, arte e innovaci\u00f3n para todo Chile!","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"\u00a1Prep\u00e1rate! Congreso Futuro 2024 desde Chile, en todas las regiones y para todo el mundo - Vinculaci\u00f3n con el Medio","og_description":"\u00a1Ciencia, tecnolog\u00eda, humanidades, arte e innovaci\u00f3n para todo Chile!","og_url":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/preparate-congreso-futuro-2024-desde-chile-en-todas-las-regiones-y-para-todo-el-mundo\/","og_site_name":"Vinculaci\u00f3n con el Medio","article_published_time":"2023-12-06T17:53:50+00:00","article_modified_time":"2023-12-07T13:31:58+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2023\/12\/Congreso-Futuro-2.png","type":"image\/png"}],"author":"Universidad de O'Higgins","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Universidad de O'Higgins","Tiempo estimado de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/preparate-congreso-futuro-2024-desde-chile-en-todas-las-regiones-y-para-todo-el-mundo\/","url":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/preparate-congreso-futuro-2024-desde-chile-en-todas-las-regiones-y-para-todo-el-mundo\/","name":"\u00a1Prep\u00e1rate! Congreso Futuro 2024 desde Chile, en todas las regiones y para todo el mundo - Vinculaci\u00f3n con el Medio","isPartOf":{"@id":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/preparate-congreso-futuro-2024-desde-chile-en-todas-las-regiones-y-para-todo-el-mundo\/#primaryimage"},"image":{"@id":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/preparate-congreso-futuro-2024-desde-chile-en-todas-las-regiones-y-para-todo-el-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2023\/12\/Congreso-Futuro-2.png","datePublished":"2023-12-06T17:53:50+00:00","dateModified":"2023-12-07T13:31:58+00:00","author":{"@id":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"description":"\u00a1Ciencia, tecnolog\u00eda, humanidades, arte e innovaci\u00f3n para todo Chile!","inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/preparate-congreso-futuro-2024-desde-chile-en-todas-las-regiones-y-para-todo-el-mundo\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/preparate-congreso-futuro-2024-desde-chile-en-todas-las-regiones-y-para-todo-el-mundo\/#primaryimage","url":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2023\/12\/Congreso-Futuro-2.png","contentUrl":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2023\/12\/Congreso-Futuro-2.png","width":1000,"height":1000},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#website","url":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/","name":"Vinculaci\u00f3n con el Medio","description":"Otro sitio de Sitios de Universidad O&#039;higgins","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f","name":"Universidad de O'Higgins","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","caption":"Universidad de O'Higgins"}}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/posts\/1075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/comments?post=1075"}],"version-history":[{"count":1,"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/posts\/1075\/revisions"}],"predecessor-version":[{"id":1077,"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/posts\/1075\/revisions\/1077"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/media\/1078"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/media?parent=1075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/categories?post=1075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/tags?post=1075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}