
{"id":121,"date":"2022-05-04T03:14:26","date_gmt":"2022-05-04T06:14:26","guid":{"rendered":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/?page_id=121"},"modified":"2022-05-04T03:14:26","modified_gmt":"2022-05-04T06:14:26","slug":"noticias","status":"publish","type":"page","link":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/noticias\/","title":{"rendered":"Noticias"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center text-right circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row][vc_column][vc_wp_custommenu nav_menu=&#8221;6&#8243;]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\"><span itemprop=\"name\">Vinculaci\u00f3n con el Medio<\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Noticias <\/span><meta itemprop=\"position\" content=\"3\" \/><\/ol><\/div><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block title--decorator  big\">Noticias<\/h1><\/div><div class=\"row filter__row m-0 horizontal\"> <form class=\"filter__form p-0 row m-0\" action=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-admin\/admin-ajax.php\" method=\"post\" id=\"filter\"><div class=\"col-12 col-md-6 filter__container-input p-0\"><div class=\"filter__icon-search\"><svg enable-background=\"new 0 0 32 32\" id=\"Editable-line\" version=\"1.1\" viewBox=\"0 0 32 32\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><circle cx=\"14\" cy=\"14\" fill=\"none\" id=\"XMLID_42_\" r=\"9\" stroke=\"#000000\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"2\"><\/circle><line fill=\"none\" id=\"XMLID_44_\" stroke=\"#000000\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" stroke-width=\"2\" x1=\"27\" x2=\"20.366\" y1=\"27\" y2=\"20.366\"><\/line><\/svg><\/div><input type=\"text\" class=\"filter__input\" placeholder=\"Buscar Novedades\" name=\"filter__form-text\" autocomplete=\"off\"\/><\/div><div class=\"col-12 col-md-6 row m-0 justify-content-end p-0\"><input type=\"hidden\" name=\"action\" value=\"uoh_filter\" \/><input type=\"hidden\" name=\"posttype\" value=\"post\" \/><div class=\"loading\"><svg version=\"1.1\" id=\"L5\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 100 100\" enable-background=\"new 0 0 0 0\" xml:space=\"preserve\">\n                  <circle fill=\"#42a0f8\" stroke=\"none\" cx=\"6\" cy=\"50\" r=\"6\">\n                    <animateTransform attributeName=\"transform\" dur=\"1s\" type=\"translate\" values=\"0 15 ; 0 -15; 0 15\" repeatCount=\"indefinite\" begin=\"0.1\"><\/animateTransform>\n                  <\/circle>\n                  <circle fill=\"#42a0f8\" stroke=\"none\" cx=\"30\" cy=\"50\" r=\"6\">\n                    <animateTransform attributeName=\"transform\" dur=\"1s\" type=\"translate\" values=\"0 10 ; 0 -10; 0 10\" repeatCount=\"indefinite\" begin=\"0.2\"><\/animateTransform>\n                  <\/circle>\n                  <circle fill=\"#42a0f8\" stroke=\"none\" cx=\"54\" cy=\"50\" r=\"6\">\n                    <animateTransform attributeName=\"transform\" dur=\"1s\" type=\"translate\" values=\"0 5 ; 0 -5; 0 5\" repeatCount=\"indefinite\" begin=\"0.3\"><\/animateTransform>\n                  <\/circle>\n                <\/svg><\/div><button type=\"submit\" class=\"button__arrow\"> <svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/button><\/div><div class=\"tags-cloud mt-4 d-block mb-1 px-0\"><div class=\"tag__input\"><input class=\"tag__input-checkbox\" type=\"checkbox\" name=\"tags[]\" value=\"16\" id=\"option-16\" > <label for=\"option-16\">Acreditaci\u00f3n UOH <\/label> <\/div><div class=\"tag__input\"><input class=\"tag__input-checkbox\" type=\"checkbox\" name=\"tags[]\" value=\"17\" id=\"option-17\" > <label for=\"option-17\">Educaci\u00f3n <\/label> <\/div><\/div><\/form><\/div>[\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1649209804184{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center text-right p-md-0 pt-5&#8243;][vc_column]<div class=\"row m-0 p-0\"><\/div><div class=\"content-holder\"><div class=\"row  swipper-news-list not--activate-hack \"><div class=\"row -wrapper\"><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2026\/04\/Inauguracion-Ano-Academico-2026-6.jpg\" alt=\"Reflexi\u00f3n universitaria: UOH inaugura A\u00f1o Acad\u00e9mico 2026 pensando en los desaf\u00edos de la Educaci\u00f3n Superior\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Mi\u00e9rcoles 29, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/reflexion-universitaria-uoh-inaugura-ano-academico-2026-pensando-en-los-desafios-de-la-educacion-superior\/\">\n                                    <h3 class=\"small-space\">Reflexi\u00f3n universitaria: UOH inaugura A\u00f1o Acad\u00e9mico 2026 pensando en los desaf\u00edos de la Educaci\u00f3n Superior<\/h3><\/a>\n\n                                    <p>La ceremonia promovi\u00f3 el an\u00e1lisis acerca de los cambios educativos que se avecinan dentro de los procesos de formaci\u00f3n universitaria ajustados a contextos digitales.   <\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/reflexion-universitaria-uoh-inaugura-ano-academico-2026-pensando-en-los-desafios-de-la-educacion-superior\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/category\/cuech\/\">\n                                        CUECH<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2026\/04\/DSC_2431-scaled.jpg\" alt=\"Universidades estatales sellan hoja de ruta 2030: Red Desarrollo Sustentable entra en fase de consolidaci\u00f3n\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/1707;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Mi\u00e9rcoles 15, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/universidades-estatales-sellan-hoja-de-ruta-2030-red-desarrollo-sustentable-entra-en-fase-de-consolidacion\/\">\n                                    <h3 class=\"small-space\">Universidades estatales sellan hoja de ruta 2030: Red Desarrollo Sustentable entra en fase de consolidaci\u00f3n<\/h3><\/a>\n\n                                    <p>En el Plenario realizado en la Universidad de O'Higgins, los 18 planteles p\u00fablicos definieron sus metas estrat\u00e9gicas para el periodo 2026-2030. El plan priorizar\u00e1 la institucionalizaci\u00f3n de capacidades, un diplomado para organismos p\u00fablicos y la medici\u00f3n de la huella h\u00eddrica en los campus.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/universidades-estatales-sellan-hoja-de-ruta-2030-red-desarrollo-sustentable-entra-en-fase-de-consolidacion\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2026\/01\/IMG_6167-scaled.jpg\" alt=\"M\u00e1s di\u00e1logo y prevenci\u00f3n para consolidar un entorno de confianza\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/1707;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Lunes 19, Enero<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/mas-dialogo-y-prevencion-para-consolidar-un-entorno-de-confianza\/\">\n                                    <h3 class=\"small-space\">M\u00e1s di\u00e1logo y prevenci\u00f3n para consolidar un entorno de confianza<\/h3><\/a>\n\n                                    <p>La visita acad\u00e9mica permiti\u00f3 vincular los contenidos del curso Modelo de Desarrollo Regional con iniciativas reales de innovaci\u00f3n, sostenibilidad y articulaci\u00f3n p\u00fablico-privada impulsadas a nivel nacional.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/mas-dialogo-y-prevencion-para-consolidar-un-entorno-de-confianza\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2026\/01\/Lanzamiento-Acreditacion-UOH-9.jpg\" alt=\"UOH inici\u00f3 Proceso de Autoevaluaci\u00f3n Institucional\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Martes 13, Enero<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/uoh-inicio-proceso-de-autoevaluacion-institucional\/\">\n                                    <h3 class=\"small-space\">UOH inici\u00f3 Proceso de Autoevaluaci\u00f3n Institucional<\/h3><\/a>\n\n                                    <p>La ceremonia marca el comienzo de un trabajo estrat\u00e9gico, participativo y de reflexi\u00f3n, orientado a fortalecer el proyecto educativo de la casa de estudios regional.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/uoh-inicio-proceso-de-autoevaluacion-institucional\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2026\/01\/36_Frontis.jpg\" alt=\"UOH cuenta con nuevo Plan de Desarrollo Estrat\u00e9gico\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Jueves 8, Enero<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/uoh-cuenta-con-nuevo-plan-de-desarrollo-estrategico\/\">\n                                    <h3 class=\"small-space\">UOH cuenta con nuevo Plan de Desarrollo Estrat\u00e9gico<\/h3><\/a>\n\n                                    <p>Su proceso de construcci\u00f3n se realiz\u00f3 entre agosto de 2024 y noviembre de 2025.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/uoh-cuenta-con-nuevo-plan-de-desarrollo-estrategico\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2025\/10\/DSC_0154-scaled.jpg\" alt=\"Carlos Mujica asume como nuevo consejero superior de la Universidad de O\u2019Higgins\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/1707;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Martes 21, Octubre<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/carlos-mujica-asume-como-nuevo-consejero-superior-de-la-universidad-de-ohiggins\/\">\n                                    <h3 class=\"small-space\">Carlos Mujica asume como nuevo consejero superior de la Universidad de O\u2019Higgins<\/h3><\/a>\n\n                                    <p>Con m\u00e1s de 40 a\u00f1os de experiencia en la Educaci\u00f3n Superior, Mujica aportar\u00e1 con su vasta trayectoria al desarrollo y planificaci\u00f3n acad\u00e9mica de la UOH.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/carlos-mujica-asume-como-nuevo-consejero-superior-de-la-universidad-de-ohiggins\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2025\/10\/Frontis-UOH.jpg\" alt=\"Comunicado Oficial: Toma Campus Rancagua\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Mi\u00e9rcoles 15, Octubre<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/comunicado-oficial-toma-campus-rancagua\/\">\n                                    <h3 class=\"small-space\">Comunicado Oficial: Toma Campus Rancagua<\/h3><\/a>\n\n                                    <p>Pasadas las 23:00 horas se acord\u00f3 deponer la toma en forma pac\u00edfica con el compromiso de no represalias a las\/os involucradas\/os y la realizaci\u00f3n de una reuni\u00f3n triestamental, a fin de identificar inquietudes de les estudiantes y funcionarias\/os.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/comunicado-oficial-toma-campus-rancagua\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2025\/09\/Cuenta-Publica-2025-18.jpg\" alt=\"Transparencia y convicci\u00f3n: Rectora presenta Cuenta P\u00fablica asegurando el compromiso con la regi\u00f3n\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Lunes 8, Septiembre<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/transparencia-y-conviccion-rectora-presenta-cuenta-publica-asegurando-el-compromiso-con-la-region\/\">\n                                    <h3 class=\"small-space\">Transparencia y convicci\u00f3n: Rectora presenta Cuenta P\u00fablica asegurando el compromiso con la regi\u00f3n<\/h3><\/a>\n\n                                    <p>Entre los desaf\u00edos que se proyectan se encuentran el nuevo proceso de acreditaci\u00f3n institucional, consolidar los estudios de postgrado e incrementar la matr\u00edcula estudiantil.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/transparencia-y-conviccion-rectora-presenta-cuenta-publica-asegurando-el-compromiso-con-la-region\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-content\/uploads\/sites\/22\/2025\/08\/CUECH.jpg\" alt=\"Universidades Estatales de Chile se suman a presi\u00f3n internacional por crisis humanitaria en Gaza\" style=\"--smush-placeholder-width: 2000px; --smush-placeholder-aspect-ratio: 2000\/1333;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Jueves 28, Agosto<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/universidades-estatales-de-chile-se-suman-a-presion-internacional-por-crisis-humanitaria-en-gaza\/\">\n                                    <h3 class=\"small-space\">Universidades Estatales de Chile se suman a presi\u00f3n internacional por crisis humanitaria en Gaza<\/h3><\/a>\n\n                                    <p>Como rectoras y rectores de las universidades p\u00fablicas del pa\u00eds, reafirmamos nuestro compromiso con la verdad, la memoria y la construcci\u00f3n de una paz duradera y estable en Palestina.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/universidades-estatales-de-chile-se-suman-a-presion-internacional-por-crisis-humanitaria-en-gaza\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pagination justify-content-center my-5\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/pages\/121\/\/page\/2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/pages\/121\/\/page\/3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/pages\/121\/\/page\/21\">21<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/pages\/121\/\/page\/2\"><div class=\"icon-pagination-next\"> <?xml version=\"1.0\" ?><svg viewBox=\"0 0 96 96\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><title\/><path d=\"M39.3756,48.0022l30.47-25.39a6.0035,6.0035,0,0,0-7.6878-9.223L26.1563,43.3906a6.0092,6.0092,0,0,0,0,9.2231L62.1578,82.615a6.0035,6.0035,0,0,0,7.6878-9.2231Z\"\/><\/svg> <\/div><\/a><\/div>[\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1649210787516{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5 pb-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center text-right&#8221;][vc_column][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_section el_class=&#8221;container mx-auto align-items-center text-right circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row][vc_column][vc_wp_custommenu nav_menu=&#8221;6&#8243;][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1649209804184{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center text-right p-md-0 pt-5&#8243;][vc_column][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1649210787516{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5 pb-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center text-right&#8221;][vc_column][\/vc_column][\/vc_row][\/vc_section]<\/p>\n","protected":false},"author":34,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-121","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Noticias - Vinculaci\u00f3n con el Medio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Noticias - Vinculaci\u00f3n con el Medio\" \/>\n<meta property=\"og:description\" content=\"[vc_section el_class=&#8221;container mx-auto align-items-center text-right circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row][vc_column][vc_wp_custommenu nav_menu=&#8221;6&#8243;][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1649209804184{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center text-right p-md-0 pt-5&#8243;][vc_column][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1649210787516{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5 pb-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center text-right&#8221;][vc_column][\/vc_column][\/vc_row][\/vc_section]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Vinculaci\u00f3n con el Medio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/noticias\/\",\"url\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/noticias\/\",\"name\":\"Noticias - Vinculaci\u00f3n con el Medio\",\"isPartOf\":{\"@id\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#website\"},\"datePublished\":\"2022-05-04T06:14:26+00:00\",\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/noticias\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#website\",\"url\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/\",\"name\":\"Vinculaci\u00f3n con el Medio\",\"description\":\"Otro sitio de Sitios de Universidad O&#039;higgins\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Noticias - Vinculaci\u00f3n con el Medio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/noticias\/","og_locale":"es_ES","og_type":"article","og_title":"Noticias - Vinculaci\u00f3n con el Medio","og_description":"[vc_section el_class=&#8221;container mx-auto align-items-center text-right circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row][vc_column][vc_wp_custommenu nav_menu=&#8221;6&#8243;][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1649209804184{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center text-right p-md-0 pt-5&#8243;][vc_column][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1649210787516{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5 pb-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center text-right&#8221;][vc_column][\/vc_column][\/vc_row][\/vc_section]","og_url":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/noticias\/","og_site_name":"Vinculaci\u00f3n con el Medio","twitter_card":"summary_large_image","twitter_misc":{"Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/noticias\/","url":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/noticias\/","name":"Noticias - Vinculaci\u00f3n con el Medio","isPartOf":{"@id":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#website"},"datePublished":"2022-05-04T06:14:26+00:00","inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/noticias\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#website","url":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/","name":"Vinculaci\u00f3n con el Medio","description":"Otro sitio de Sitios de Universidad O&#039;higgins","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/pages\/121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/comments?post=121"}],"version-history":[{"count":1,"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/pages\/121\/revisions"}],"predecessor-version":[{"id":122,"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/pages\/121\/revisions\/122"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/media?parent=121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}