
{"id":30,"count":3,"description":"","link":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/category\/salud-uoh\/","name":"Salud UOH","slug":"salud-uoh","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Salud UOH Archives - Vinculaci\u00f3n con el Medio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/category\/salud-uoh\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salud UOH Archives - Vinculaci\u00f3n con el Medio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/category\/salud-uoh\/\" \/>\n<meta property=\"og:site_name\" content=\"Vinculaci\u00f3n con el Medio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/category\/salud-uoh\/\",\"url\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/category\/salud-uoh\/\",\"name\":\"Salud UOH Archives - Vinculaci\u00f3n con el Medio\",\"isPartOf\":{\"@id\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#website\"},\"inLanguage\":\"es-CL\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#website\",\"url\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/\",\"name\":\"Vinculaci\u00f3n con el Medio\",\"description\":\"Otro sitio de Sitios de Universidad O&#039;higgins\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salud UOH Archives - Vinculaci\u00f3n con el Medio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/category\/salud-uoh\/","og_locale":"es_ES","og_type":"article","og_title":"Salud UOH Archives - Vinculaci\u00f3n con el Medio","og_url":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/category\/salud-uoh\/","og_site_name":"Vinculaci\u00f3n con el Medio","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/category\/salud-uoh\/","url":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/category\/salud-uoh\/","name":"Salud UOH Archives - Vinculaci\u00f3n con el Medio","isPartOf":{"@id":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#website"},"inLanguage":"es-CL"},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/#website","url":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/","name":"Vinculaci\u00f3n con el Medio","description":"Otro sitio de Sitios de Universidad O&#039;higgins","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/categories\/30","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.uoh.cl\/vinculacion-con-el-medio\/wp-json\/wp\/v2\/posts?categories=30"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}