
{"id":2810,"date":"2025-09-30T15:59:19","date_gmt":"2025-09-30T18:59:19","guid":{"rendered":"https:\/\/www.uoh.cl\/postgrado\/?page_id=2810"},"modified":"2025-12-22T17:38:21","modified_gmt":"2025-12-22T20:38:21","slug":"admision","status":"publish","type":"page","link":"https:\/\/www.uoh.cl\/postgrado\/magister-en-metodologia-de-investigacion-social-interdisciplinaria-inicio\/admision\/","title":{"rendered":"Mag\u00edster en Metodolog\u00eda de Investigaci\u00f3n Social Interdisciplinaria Admisi\u00f3n"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]<div class=\"uoh_slider_featured_component component__featured-slide row mx-auto col-12 m-0 align-items-center position-relative lazyload\" style=\" background:inherit\" data-bg=\"url(https:\/\/www.uoh.cl\/postgrado\/wp-content\/uploads\/sites\/36\/2025\/10\/Magister-en-Metodologia-de-Investigacion-Social-Interdisciplinaria.png)\"><div class=\"caption--degrade\"><svg  xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"1061px\" height=\"539px\"><defs><linearGradient id=\"PSgrad_0\" x1=\"0%\" x2=\"64.279%\" y1=\"76.604%\" y2=\"0%\"><stop offset=\"0%\" stop-color=\"rgb(66,160,248)\" stop-opacity=\"1\" \/><stop offset=\"100%\" stop-color=\"rgb(66,160,248)\" stop-opacity=\"0\" \/><\/linearGradient><\/defs><path fill-rule=\"evenodd\"  fill=\"none\" d=\"M311.000,515.000 C311.000,515.000 211.039,468.555 132.000,357.000 C21.864,201.555 -4.306,4.695 1.000,0.000 L196.000,0.000 L811.000,0.000 L1061.000,0.000 C1061.000,0.000 851.535,430.030 546.000,521.000 C402.674,563.674 311.000,515.000 311.000,515.000 Z\"\/> <path fill=\"url(#PSgrad_0)\"d=\"M311.000,515.000 C311.000,515.000 211.039,468.555 132.000,357.000 C21.864,201.555 -4.306,4.695 1.000,0.000 L196.000,0.000 L811.000,0.000 L1061.000,0.000 C1061.000,0.000 851.535,430.030 546.000,521.000 C402.674,563.674 311.000,515.000 311.000,515.000 Z\"\/><\/svg><\/div><div class=\"caption--quote\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"width=\"226px\" height=\"273px\"><defs><linearGradient id=\"PSgrad_0\" x1=\"71.934%\" x2=\"0%\" y1=\"69.466%\" y2=\"0%\"><stop offset=\"0%\" stop-color=\"rgb(66,160,248)\" stop-opacity=\"0.49\" \/><stop offset=\"100%\" stop-color=\"rgb(66,160,248)\" stop-opacity=\"0\" \/><\/linearGradient><\/defs><path fill-rule=\"evenodd\"  fill=\"none\" d=\"M-0.000,273.000 L174.000,273.000 C174.000,273.000 226.000,266.268 226.000,221.000 C226.000,175.732 226.000,-0.000 226.000,-0.000 C226.000,-0.000 24.577,71.878 -0.000,273.000 Z\"\/><path fill=\"url(#PSgrad_0)\"d=\"M-0.000,273.000 L174.000,273.000 C174.000,273.000 226.000,266.268 226.000,221.000 C226.000,175.732 226.000,-0.000 226.000,-0.000 C226.000,-0.000 24.577,71.878 -0.000,273.000 Z\"\/><\/svg><\/div><div class=\"my-uoh_slider_featured_component container mx-auto p-md-0\" ><div class=\"content component__featured-slide-content container row mx-auto aling-items-center p-0\"><h1 class=\"p-0 featured-slide title\"  style=\"\"><em>Mag\u00edster en Metodolog\u00eda de Investigaci\u00f3n Social Interdisciplinaria<\/em>Admisi\u00f3n<\/h1><\/div><span><\/span><\/div><\/div>[\/vc_column][\/vc_row][vc_section el_class=&#8221;circle&#8211;pattern pb-4&#8243; css=&#8221;.vc_custom_1759259942291{padding-top: 3rem !important;}&#8221; el_id=&#8221;requisitos&#8221;][vc_row el_class=&#8221;container mx-auto align-items-center&#8221;][vc_column width=&#8221;1\/2&#8243;]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/postgrado\"><span itemprop=\"name\">Direcci\u00f3n de Postgrado<\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/postgrado\/magister-en-metodologia-de-investigacion-social-interdisciplinaria-inicio\/\"><span itemprop=\"name\">Mag\u00edster en Metodolog\u00eda de Investigaci\u00f3n Social Interdisciplinaria Inicio<\/span><\/a><meta itemprop=\"position\" content=\"3\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Mag\u00edster en Metodolog\u00eda de Investigaci\u00f3n Social Interdisciplinaria Admisi\u00f3n <\/span><meta itemprop=\"position\" content=\"4\" \/><\/ol><\/div>[\/vc_column][vc_column width=&#8221;1\/2&#8243;][\/vc_column][\/vc_row][vc_row el_class=&#8221;container mx-auto align-items-start&#8221;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1693338597452{padding-right: 2rem !important;}&#8221;]<div class=\"uoh_title_component-container\"><h2 class=\"title title--ms d-inline-block title--decorator  medium\">Requisitos de postulaci\u00f3n<\/h2><\/div>[vc_tta_accordion style=&#8221;modern&#8221; active_section=&#8221;1&#8243; collapsible_all=&#8221;true&#8221;][vc_tta_section i_position=&#8221;right&#8221; i_icon_fontawesome=&#8221;fas fa-pencil-alt&#8221; add_icon=&#8221;true&#8221; title=&#8221;Requisitos de postulaci\u00f3n&#8221; tab_id=&#8221;1692372173513-bb958d50-bdb4&#8243;][vc_column_text css=&#8221;&#8221;]<span class=\"TextRun SCXW191387611 BCX0\" lang=\"ES-CL\" xml:lang=\"ES-CL\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW191387611 BCX0\">Contar con el grado acad\u00e9mico de Licenciatura en Ciencias Sociales o disciplinas afines, conferido por universidades nacionales o extranjeras. Para t\u00edtulos o grados extranjeros se solicita que el nivel y contenido de estudios sean equivalentes a los necesarios para obtener el grado de Licenciado\/a <\/span><span class=\"NormalTextRun AdvancedProofingIssueV2Themed SCXW191387611 BCX0\">de acuerdo a<\/span><span class=\"NormalTextRun SCXW191387611 BCX0\"> la evaluaci\u00f3n del Comit\u00e9 del Programa.<\/span><\/span><span class=\"EOP SCXW191387611 BCX0\" data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span>[\/vc_column_text][\/vc_tta_section][vc_tta_section title=&#8221;Admisibilidad&#8221; tab_id=&#8221;1697469372946-5b38cab7-d3ef&#8221;][vc_column_text css=&#8221;&#8221;]<\/p>\n<ul>\n<li data-leveltext=\"\uf02d\" data-font=\"Symbol\" data-listid=\"4\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf02d&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Completar el formulario de postulaci\u00f3n en l\u00ednea<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/li>\n<li data-leveltext=\"\uf02d\" data-font=\"Symbol\" data-listid=\"4\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf02d&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Presentar el certificado de grado acad\u00e9mico de Licenciatura en Ciencias Sociales, o disciplinas afines. En el caso de extranjeras\/os, t\u00edtulo profesional equivalente al grado de licenciado en Chile.<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/li>\n<li data-leveltext=\"\uf02d\" data-font=\"Symbol\" data-listid=\"4\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf02d&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Presentar certificado de notas de pregrado.<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/li>\n<li data-leveltext=\"\uf02d\" data-font=\"Symbol\" data-listid=\"4\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf02d&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Presentar certificado de ranking de pregrado.<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/li>\n<li data-leveltext=\"\uf02d\" data-font=\"Symbol\" data-listid=\"4\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf02d&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Presentar Curr\u00edculum Vitae actualizado indicando trayectoria profesional y acad\u00e9mica.<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/li>\n<li data-leveltext=\"\uf02d\" data-font=\"Symbol\" data-listid=\"4\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf02d&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Presentar una carta de motivaci\u00f3n indicando intereses personales de investigaci\u00f3n y el \u00e1rea de inter\u00e9s a desarrollar.<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/li>\n<li data-leveltext=\"\uf02d\" data-font=\"Symbol\" data-listid=\"4\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf02d&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Entregar dos referencias acad\u00e9micas o profesionales para solicitar carta de recomendaci\u00f3n.<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/li>\n<li data-leveltext=\"\uf02d\" data-font=\"Symbol\" data-listid=\"4\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf02d&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Presentar copia de c\u00e9dula de identidad o pasaporte vigente.<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_tta_section][vc_tta_section i_position=&#8221;right&#8221; i_icon_fontawesome=&#8221;fas fa-file-alt&#8221; add_icon=&#8221;true&#8221; title=&#8221;Documentos para postular&#8221; tab_id=&#8221;1692372173515-776f4718-b038&#8243;][vc_column_text css=&#8221;&#8221;]<\/p>\n<ul>\n<li><span data-contrast=\"none\">Solicitud de postulaci\u00f3n. Corresponde al formulario a completar en la plataforma de postulaci\u00f3n <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/li>\n<li>Certificado de grado acad\u00e9mico de Licenciado\/a, o su equivalente. En el caso de postulantes extranjeros\/as, el certificado debe estar legalizado con el apostillado o visado en el Consulado de Chile del pa\u00eds correspondiente. <span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/li>\n<li>Certificado de concentraci\u00f3n de notas de pregrado. Debe contener el desglose de las calificaciones obtenidas -aprobadas y reprobadas- en las asignaturas del programa, emitido por la autoridad correspondiente, con su respectiva escala de evaluaci\u00f3n. <span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/li>\n<li>Certificado de Ranking de pregrado. Documento que certifica la posici\u00f3n del\/la estudiante al momento de su egreso o titulaci\u00f3n en relaci\u00f3n con el n\u00famero total de alumnos\/as de su generaci\u00f3n de egreso o titulaci\u00f3n. Debe ser emitido por la autoridad correspondiente. En su defecto, debe presentar el certificado de su Instituci\u00f3n que acredite que no provee tal informaci\u00f3n. <span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/li>\n<li>Curr\u00edculum Vitae seg\u00fan <strong><em><a href=\"https:\/\/www.uoh.cl\/postgrado\/wp-content\/uploads\/sites\/36\/2025\/10\/UOH_cv_Mg.-en-Metodologia-de-Investigacion-Social-Interdisciplinaria.docx\" target=\"_blank\" rel=\"noopener\">formato entregado por el programa<\/a><\/em><\/strong><span data-contrast=\"none\">.\u00a0<\/span><\/li>\n<li>Carta de Motivaci\u00f3n. M\u00e1ximo de 1000 palabras. Documento en formato libre en la cual el\/la postulante debe referirse a los siguientes aspectos:<br \/>\n<span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u2022 <\/span><span data-contrast=\"none\">Proyecciones acad\u00e9micas y motivaci\u00f3n por cursar el programa;<br \/>\n<\/span><span data-contrast=\"none\">\u2022 Idea preliminar de proyecto de investigaci\u00f3n y adherencia a las \u00e1reas de investigaci\u00f3n del Programa y del ICSo. <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/li>\n<li>Dos referencias acad\u00e9micas o profesionales. Debe indicar en la plataforma de postulaci\u00f3n dos referencias y sus respectivas direcciones electr\u00f3nicas.<br \/>\nDebe establecer contacto con sus recomendadores\/as para que completen la <a href=\"https:\/\/www.uoh.cl\/postgrado\/wp-content\/uploads\/sites\/36\/2025\/12\/uoh_carta_recomendacion_postgrado.docx\" target=\"_blank\" rel=\"noopener\"><strong><em>carta de recomendaci\u00f3n<\/em><\/strong><\/a>. Es importante que dichas cartas sean enviadas directamente por las personas recomendadoras indicadas en el formulario de postulaci\u00f3n al correo electr\u00f3nico: postulaciones.postgrado@uoh.cl.<br \/>\nEl plazo m\u00e1ximo de env\u00edo de las cartas de recomendaci\u00f3n es hasta el viernes 02 de enero 2026, a las 23:59 horas. No se aceptar\u00e1n cartas enviadas por los\/as postulantes.<\/li>\n<li>Fotocopia de c\u00e9dula de identidad o pasaporte vigente <span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_tta_section][vc_tta_section title=&#8221;Consultas&#8221; tab_id=&#8221;1697469457403-ff3330bf-a7c4&#8243;][vc_column_text css=&#8221;&#8221;]<span class=\"TextRun SCXW53730855 BCX0\" lang=\"ES-CL\" xml:lang=\"ES-CL\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW53730855 BCX0\">En caso de consultas escribir al mail: <\/span><\/span><a class=\"Hyperlink SCXW53730855 BCX0\" href=\"mailto:postulaciones.postgrado@uoh.cl\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"TextRun Underlined SCXW53730855 BCX0\" lang=\"ES-CL\" xml:lang=\"ES-CL\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW53730855 BCX0\" data-ccp-charstyle=\"Hyperlink\">postulaciones.postgrado@uoh.cl<\/span><\/span><\/a><span class=\"TextRun Underlined SCXW53730855 BCX0\" lang=\"ES-CL\" xml:lang=\"ES-CL\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW53730855 BCX0\" data-ccp-charstyle=\"Hyperlink\">. C<\/span><\/span><span class=\"TextRun SCXW53730855 BCX0\" lang=\"ES-CL\" xml:lang=\"ES-CL\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW53730855 BCX0\">onsidere que el horario de atenci\u00f3n administrativa es de lunes a jueves de 09:00 a 18:00 horas, viernes de 09:00 a 17:00 horas.\u00a0<\/span><\/span><span class=\"EOP SCXW53730855 BCX0\" data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span>[\/vc_column_text][\/vc_tta_section][vc_tta_section i_position=&#8221;right&#8221; i_icon_fontawesome=&#8221;&#8221; add_icon=&#8221;true&#8221; title=&#8221;Postulaciones&#8221; tab_id=&#8221;1692372173514-eaf9a46b-9c4e&#8221;][vc_column_text css=&#8221;&#8221;]<span data-contrast=\"none\">Las postulaciones deben ser enviadas en <a href=\"https:\/\/ucampus.uoh.cl\/m\/postulante\/procesos_abiertos\" target=\"_blank\" rel=\"noopener\">ESTE ENLACE<\/a>.<\/span><\/p>\n<ul>\n<li><span data-contrast=\"none\">Plazo de postulaciones hasta el 02 de enero de 2026.<\/span><\/li>\n<\/ul>\n<p style=\"text-align: justify\">Los\/as recomendadores\/as deben enviar directamente las cartas de recomendaci\u00f3n al correo: <a href=\"mailto:postulaciones.postgrado@uoh.cl\">postulaciones.postgrado@uoh.cl<\/a>. Plazo hasta el 02 de enero 2026. No se aceptar\u00e1n cartas enviadas por los\/as postulantes.<\/p>\n<p>[\/vc_column_text][\/vc_tta_section][vc_tta_section i_position=&#8221;right&#8221; i_icon_fontawesome=&#8221;fas fa-calendar-check&#8221; add_icon=&#8221;true&#8221; title=&#8221;Proceso de selecci\u00f3n&#8221; tab_id=&#8221;1692372173515-cf25df51-1d23&#8243;][vc_column_text css=&#8221;&#8221;]<b><span data-contrast=\"none\">1. Admisibilidad de la postulaci\u00f3n: <\/span><\/b><span data-contrast=\"none\">La Direcci\u00f3n de Postgrado proceder\u00e1 a revisar la completitud de los documentos de la postulaci\u00f3n y verificar\u00e1 el cumplimiento de los documentos enviados a la plataforma de postulaci\u00f3n provista por la Direcci\u00f3n de Postgrado. Las postulaciones incompletas no ser\u00e1n admitidas para la siguiente etapa de selecci\u00f3n, mientras que las postulaciones admitidas continuar\u00e1n con la siguiente etapa de evaluaci\u00f3n realizada por el Comit\u00e9 del Programa.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"none\">2. Evaluaci\u00f3n del grado acad\u00e9mico: <\/span><\/b><span data-contrast=\"none\">El Comit\u00e9 del Programa realiza una revisi\u00f3n de los antecedentes considera los siguientes criterios:<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<table data-tablestyle=\"MsoTableGrid\" data-tablelook=\"1184\">\n<tbody>\n<tr>\n<td data-celllook=\"4369\"><b><span data-contrast=\"none\">Criterio<\/span><\/b><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:200}\">\u00a0<\/span><\/td>\n<td data-celllook=\"4369\"><b><span data-contrast=\"none\">Descriptor<\/span><\/b><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:200}\">\u00a0<\/span><\/td>\n<\/tr>\n<tr>\n<td data-celllook=\"4369\"><span data-contrast=\"none\">1. Formaci\u00f3n en Ciencias Sociales<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:200}\">\u00a0<\/span><\/td>\n<td data-celllook=\"4369\"><span data-contrast=\"none\">La formaci\u00f3n en Ciencias Sociales equivalente a lo declarado en el grado acad\u00e9mico de Licenciatura.<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:200}\">\u00a0<\/span><\/td>\n<\/tr>\n<tr>\n<td data-celllook=\"4369\"><span data-contrast=\"none\">2. Formaci\u00f3n en disciplinas afines al programa<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:200}\">\u00a0<\/span><\/td>\n<td data-celllook=\"4369\"><span data-contrast=\"none\">Formaci\u00f3n disciplinar pertinente al tema de desarrollo del Mag\u00edster: Metodolog\u00eda de Investigaci\u00f3n Social Interdisciplinaria u otra disciplina af\u00edn a evaluar por el Comit\u00e9 del programa.<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:200}\">\u00a0<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span data-contrast=\"none\">Si la persona postulante cuenta con el grado de Licenciatura en disciplinas de las Ciencias Sociales (criterio 1) o cumpla el criterio 2 se\u00f1alado, se procede a la siguiente etapa de selecci\u00f3n.\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">No obstante, el Comit\u00e9 del Programa podr\u00e1 determinar que un\/a candidato\/a cuenta con una formaci\u00f3n disciplinar pertinente al desarrollo del Mag\u00edster, pero su preparaci\u00f3n no es totalmente suficiente para el desarrollo normal del programa. En este caso, el Comit\u00e9 podr\u00e1 recomendar la selecci\u00f3n del\/de la candidato\/a en el programa, quien tendr\u00e1 que realizar la evaluaci\u00f3n inicial de conocimientos en el curso de nivelaci\u00f3n disponible en la malla curricular del Programa.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"none\">3. Evaluaci\u00f3n de antecedentes acad\u00e9micos y\/o profesionales:<\/span><\/b><span data-contrast=\"none\"> Los antecedentes en esta etapa ser\u00e1n evaluados a trav\u00e9s de r\u00fabricas por el Comit\u00e9 del Programa siguiendo los siguientes criterios y subcriterios:<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<table data-tablestyle=\"MsoTableGrid\" data-tablelook=\"1536\">\n<tbody>\n<tr>\n<td data-celllook=\"4369\"><b><span data-contrast=\"auto\">Criterio<\/span><\/b><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/td>\n<td data-celllook=\"4369\"><b><span data-contrast=\"auto\">Subcriterio<\/span><\/b><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/td>\n<td data-celllook=\"4369\"><b><span data-contrast=\"auto\">Evidencia<\/span><\/b><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/td>\n<\/tr>\n<tr>\n<td data-celllook=\"4369\"><span data-contrast=\"auto\">Antecedentes acad\u00e9micos<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">35%<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/td>\n<td colspan=\"1\" rowspan=\"2\" data-celllook=\"4369\"><span data-contrast=\"auto\">Antecedentes acad\u00e9micos de pregrado.<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/td>\n<td data-celllook=\"4369\"><span data-contrast=\"auto\">Concentraci\u00f3n de notas de pregrado<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/td>\n<\/tr>\n<tr>\n<td data-celllook=\"0\"><span data-ccp-props=\"{}\">\u00a0<\/span><\/td>\n<td data-celllook=\"4369\"><span data-contrast=\"auto\">Ranking de egreso<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/td>\n<\/tr>\n<tr>\n<td data-celllook=\"4369\"><span data-contrast=\"auto\">Trayectoria<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">30%<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/td>\n<td data-celllook=\"4369\"><span data-contrast=\"auto\">Actividades de ayudant\u00edas, docencia,\u00a0<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">investigaci\u00f3n, desarrollo profesional\u00a0<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">y otros antecedentes de pregrado.<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/td>\n<td data-celllook=\"4369\"><span data-contrast=\"auto\">Curr\u00edculum Vitae<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/td>\n<\/tr>\n<tr>\n<td data-celllook=\"4369\"><span data-contrast=\"auto\">Carta de motivaci\u00f3n<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">35%<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/td>\n<td data-celllook=\"4369\"><span data-contrast=\"auto\">Proyecciones acad\u00e9micas y motivaci\u00f3n por cursar el programa.<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/td>\n<td colspan=\"1\" rowspan=\"2\" data-celllook=\"4369\"><span data-contrast=\"auto\">Carta de motivaci\u00f3n<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/td>\n<\/tr>\n<tr>\n<td data-celllook=\"0\"><span data-ccp-props=\"{}\">\u00a0<\/span><\/td>\n<td data-celllook=\"4369\"><span data-contrast=\"auto\">Idea preliminar de proyecto de investigaci\u00f3n y adherencia a las \u00e1reas de investigaci\u00f3n del Programa y del ICSo.<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><b><span data-contrast=\"none\">4.- Evaluaci\u00f3n de referencias acad\u00e9micas y\/o profesionales y entrevista: <\/span><\/b><span data-contrast=\"none\">El Comit\u00e9 del Programa, a partir de la etapa de revisi\u00f3n de antecedentes, realizar\u00e1 una pre-selecci\u00f3n de postulantes quienes ser\u00e1n convocados\/as a esta etapa. Su evaluaci\u00f3n se guiar\u00e1 por las siguientes ponderaciones:<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<table data-tablestyle=\"MsoTableGrid\" data-tablelook=\"1184\">\n<tbody>\n<tr>\n<td data-celllook=\"4369\"><b><span data-contrast=\"auto\">Criterio<\/span><\/b><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/td>\n<td data-celllook=\"4369\"><b><span data-contrast=\"auto\">Ponderaci\u00f3n<\/span><\/b><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/td>\n<\/tr>\n<tr>\n<td data-celllook=\"4369\"><span data-contrast=\"auto\">Cartas de recomendaci\u00f3n<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/td>\n<td data-celllook=\"4369\"><span data-contrast=\"auto\">30%<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/td>\n<\/tr>\n<tr>\n<td data-celllook=\"4369\"><span data-contrast=\"auto\">Entrevista<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/td>\n<td data-celllook=\"4369\"><span data-contrast=\"auto\">70%<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span data-contrast=\"none\">El Comit\u00e9 del Programa se reserva el derecho de no llenar todas las vacantes disponibles.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">El Comit\u00e9 del Programa se reserva el derecho a solicitar m\u00e1s antecedentes al\/a la postulante.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">La resoluci\u00f3n de aceptaci\u00f3n o rechazo de la postulaci\u00f3n ser\u00e1 informada a cada postulante por escrito mediante una carta formal enviada al correo electr\u00f3nico indicado en la plataforma de postulaci\u00f3n.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:240}\">\u00a0<\/span>[\/vc_column_text][\/vc_tta_section][\/vc_tta_accordion][vc_column_text][\/vc_column_text][vc_zigzag color=&#8221;white&#8221; el_border_width=&#8221;20&#8243; el_class=&#8221;opacity-0&#8243;][vc_zigzag color=&#8221;white&#8221; el_border_width=&#8221;20&#8243; el_class=&#8221;opacity-0&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1693339200251{padding-left: 2rem !important;background-image: url(https:\/\/www.uoh.cl\/postgrado\/wp-content\/uploads\/sites\/36\/2023\/08\/unsplash_5fNmWej4tAA.jpg?id=501) !important;border-radius: 15px !important;}&#8221;][vc_row_inner el_id=&#8221;postula_inner&#8221; el_class=&#8221;rounded shadow p-4 mt-0 mx-2 mx-md-4&#8243; css=&#8221;.vc_custom_1693339304635{margin-top: 70px !important;background-color: #ffffff !important;}&#8221;][vc_column_inner][vc_column_text css=&#8221;&#8221;]<\/p>\n<h5><strong>Convocatoria a postulaciones 2026:<\/strong><\/h5>\n<div>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div>\n<p>Hasta el 02 de enero de 2026.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_zigzag color=&#8221;white&#8221;]<div class=\"uoh_link_component pe-4 d-inline-block py-1 button_white inline\"><a href=\"mailto:postulaciones.postgrado@uoh.cl\"\n                                    class=\"link link--bold component__btn-content\"\n                                    title\"\"\n                                    target=\"_blank\"\n                                    rel=\"\">Consultas<span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><div class=\"uoh_link_component pe-4 d-inline-block py-1 button_white inline\"><a href=\"https:\/\/www.uoh.cl\/postgrado\/wp-content\/uploads\/sites\/36\/2025\/12\/Instructivo-de-postulacion-programas-de-postgrado-02-01-2026.pdf\"\n                                    class=\"link link--bold component__btn-content\"\n                                    title\"\"\n                                    target=\"_blank\"\n                                    rel=\"\">Instructivo de postulaci\u00f3n<span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><div class=\"uoh_link_component pe-4 left py-1 button_white left\"><a href=\"https:\/\/ucampus.uoh.cl\/m\/postulante\/procesos_abiertos\"\n                                    class=\"link link--bold component__btn-content\"\n                                    title\"\"\n                                    target=\"_blank\"\n                                    rel=\"\">Iniciar postulaci\u00f3n<span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_section el_class=&#8221;pb-4&#8243; css=&#8221;.vc_custom_1759259956119{padding-top: 3rem !important;background-color: #f7faff !important;}&#8221; el_id=&#8221;arancel&#8221;][vc_row el_class=&#8221;container mx-auto align-items-center&#8221;][vc_column][vc_row_inner][vc_column_inner width=&#8221;2\/3&#8243;]<div class=\"uoh_link_component pe-4 d-inline-block py-1 button_white inline\"><a href=\"https:\/\/www.uoh.cl\/postgrado\/beneficios\/\"\n                                    class=\"link link--bold component__btn-content\"\n                                    title\"Becas y beneficios Postgrado UOH\"\n                                    target=\"_blank\"\n                                    rel=\"\">Revisa informaci\u00f3n de becas y beneficios<span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]<div class=\"uoh_simple_image_component component__simple_image simple__image-right col-12\"><div class=\"uoh_simple_image_component\"><figure class=\"simple_image_contain\"><div> <img decoding=\"async\" data-src=\"https:\/\/www.uoh.cl\/postgrado\/wp-content\/uploads\/sites\/36\/2023\/08\/Foto-becas.jpg\" class=\"w-100 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/989;\"> <\/div><\/figure><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1693341925001{padding-top: 5rem !important;padding-bottom: 3rem !important;background-color: #53575a !important;}&#8221; el_class=&#8221;text-white text-light pb-4&#8243; el_id=&#8221;sitemap&#8221;][vc_row el_class=&#8221;container mx-auto align-items-start&#8221;][vc_column width=&#8221;1\/5&#8243;]<div class=\"uoh_title_component-container\"><h4 class=\"title title--ms d-inline-block title--decorator  small\">Presentaci\u00f3n<\/h4><\/div><div class=\"uoh_link_component pe-4 left py-1 simple left\"><a href=\"https:\/\/www.uoh.cl\/postgrado\/magister-en-metodologia-de-investigacion-social-interdisciplinaria-inicio\/informacion\/\"\n                                    class=\"link link--bold component__btn-content\"\n                                    title\"\"\n                                    target=\"\"\n                                    rel=\"\">Mag\u00edster<span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><div class=\"uoh_link_component pe-4 left py-1 simple left\"><a href=\"https:\/\/www.uoh.cl\/postgrado\/magister-en-metodologia-de-investigacion-social-interdisciplinaria-inicio\/informacion\/#perfil\"\n                                    class=\"link link--bold component__btn-content\"\n                                    title\"Mag\u00edster\"\n                                    target=\"\"\n                                    rel=\"\">Perfil de graduaci\u00f3n<span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div>[vc_zigzag color=&#8221;white&#8221; el_border_width=&#8221;20&#8243; el_class=&#8221;opacity-0&#8243;][\/vc_column][vc_column width=&#8221;1\/5&#8243; el_class=&#8221;d-flex flex-wrap flex-column&#8221;]<div class=\"uoh_title_component-container\"><h4 class=\"title title--ms d-inline-block title--decorator  small\">Programa<\/h4><\/div><div class=\"uoh_link_component pe-4 left py-1 simple left\"><a href=\"https:\/\/www.uoh.cl\/postgrado\/magister-en-metodologia-de-investigacion-social-interdisciplinaria-inicio\/programa\/\"\n                                    class=\"link link--bold component__btn-content\"\n                                    title\"\"\n                                    target=\"\"\n                                    rel=\"\">\u00c1reas de investigaci\u00f3n<span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><div class=\"uoh_link_component pe-4 left py-1 simple left\"><a href=\"https:\/\/www.uoh.cl\/postgrado\/magister-en-metodologia-de-investigacion-social-interdisciplinaria-inicio\/programa\/#programa\"\n                                    class=\"link link--bold component__btn-content\"\n                                    title\"Programa\"\n                                    target=\"\"\n                                    rel=\"\">Programa de estudios<span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><div class=\"uoh_link_component pe-4 left py-1 simple left\"><a href=\"https:\/\/www.uoh.cl\/postgrado\/magister-en-metodologia-de-investigacion-social-interdisciplinaria-inicio\/programa\/#cuerpo-academico\"\n                                    class=\"link link--bold component__btn-content\"\n                                    title\"Programa\"\n                                    target=\"\"\n                                    rel=\"\">Cuerpo Acad\u00e9mico<span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div>[vc_zigzag color=&#8221;white&#8221; el_border_width=&#8221;20&#8243; el_class=&#8221;opacity-0&#8243;][\/vc_column][vc_column width=&#8221;1\/5&#8243; el_class=&#8221;d-flex flex-wrap flex-column&#8221;]<div class=\"uoh_title_component-container\"><h4 class=\"title title--ms d-inline-block title--decorator  small\">Admisi\u00f3n<\/h4><\/div><div class=\"uoh_link_component pe-4 left py-1 simple left\"><a href=\"https:\/\/www.uoh.cl\/postgrado\/magister-en-metodologia-de-investigacion-social-interdisciplinaria-inicio\/admision\/\"\n                                    class=\"link link--bold component__btn-content\"\n                                    title\"\"\n                                    target=\"\"\n                                    rel=\"\">Requisitos de postulaci\u00f3n<span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><div class=\"uoh_link_component pe-4 left py-1 simple left\"><a href=\"https:\/\/www.uoh.cl\/postgrado\/magister-en-metodologia-de-investigacion-social-interdisciplinaria-inicio\/admision\/#arancel\"\n                                    class=\"link link--bold component__btn-content\"\n                                    title\"\"\n                                    target=\"\"\n                                    rel=\"\">Arancel<span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div>[vc_zigzag color=&#8221;white&#8221; el_border_width=&#8221;20&#8243; el_class=&#8221;opacity-0&#8243;][\/vc_column][vc_column width=&#8221;1\/5&#8243;]<div class=\"uoh_title_component-container\"><h4 class=\"title title--ms d-inline-block title--decorator  small\">Becas<\/h4><\/div><div class=\"uoh_link_component pe-4 left py-1 simple left\"><a href=\"https:\/\/www.uoh.cl\/postgrado\/beneficios\/\"\n                                    class=\"link link--bold component__btn-content\"\n                                    title\"\"\n                                    target=\"\"\n                                    rel=\"\">Becas y beneficios<span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div>[\/vc_column][vc_column width=&#8221;1\/5&#8243;]<div class=\"uoh_simple_image_component component__simple_image simple__image-right col-12\"><div class=\"uoh_simple_image_component\"><figure class=\"simple_image_contain\"><div> <img decoding=\"async\" data-src=\"https:\/\/www.uoh.cl\/postgrado\/wp-content\/uploads\/sites\/36\/2025\/10\/Magister-en-Metodologia-de-Investigacion-Social-Interdisciplinaria-1.png\" class=\"w-100 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1000px; --smush-placeholder-aspect-ratio: 1000\/1000;\"> <\/div><\/figure><\/div><\/div>[\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row][vc_section el_class=&#8221;circle&#8211;pattern pb-4&#8243; css=&#8221;.vc_custom_1759259942291{padding-top: 3rem !important;}&#8221; el_id=&#8221;requisitos&#8221;][vc_row el_class=&#8221;container mx-auto align-items-center&#8221;][vc_column width=&#8221;1\/2&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][\/vc_column][\/vc_row][vc_row el_class=&#8221;container mx-auto align-items-start&#8221;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1693338597452{padding-right: 2rem !important;}&#8221;][vc_tta_accordion style=&#8221;modern&#8221; active_section=&#8221;1&#8243; collapsible_all=&#8221;true&#8221;][vc_tta_section i_position=&#8221;right&#8221; i_icon_fontawesome=&#8221;fas fa-pencil-alt&#8221; add_icon=&#8221;true&#8221; title=&#8221;Requisitos de postulaci\u00f3n&#8221; tab_id=&#8221;1692372173513-bb958d50-bdb4&#8243;][vc_column_text css=&#8221;&#8221;]Contar con el grado acad\u00e9mico de Licenciatura en Ciencias Sociales o disciplinas afines, conferido por universidades nacionales o extranjeras. Para t\u00edtulos o grados extranjeros se [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":0,"parent":2794,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2810","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mag\u00edster en Metodolog\u00eda de Investigaci\u00f3n Social Interdisciplinaria Admisi\u00f3n - Direcci\u00f3n de Postgrado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uoh.cl\/postgrado\/magister-en-metodologia-de-investigacion-social-interdisciplinaria-inicio\/admision\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mag\u00edster en Metodolog\u00eda de Investigaci\u00f3n Social Interdisciplinaria Admisi\u00f3n - Direcci\u00f3n de Postgrado\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][\/vc_column][\/vc_row][vc_section el_class=&#8221;circle&#8211;pattern pb-4&#8243; css=&#8221;.vc_custom_1759259942291{padding-top: 3rem !important;}&#8221; el_id=&#8221;requisitos&#8221;][vc_row el_class=&#8221;container mx-auto align-items-center&#8221;][vc_column width=&#8221;1\/2&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][\/vc_column][\/vc_row][vc_row el_class=&#8221;container mx-auto align-items-start&#8221;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1693338597452{padding-right: 2rem !important;}&#8221;][vc_tta_accordion style=&#8221;modern&#8221; active_section=&#8221;1&#8243; collapsible_all=&#8221;true&#8221;][vc_tta_section i_position=&#8221;right&#8221; i_icon_fontawesome=&#8221;fas fa-pencil-alt&#8221; add_icon=&#8221;true&#8221; title=&#8221;Requisitos de postulaci\u00f3n&#8221; tab_id=&#8221;1692372173513-bb958d50-bdb4&#8243;][vc_column_text css=&#8221;&#8221;]Contar con el grado acad\u00e9mico de Licenciatura en Ciencias Sociales o disciplinas afines, conferido por universidades nacionales o extranjeras. Para t\u00edtulos o grados extranjeros se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/postgrado\/magister-en-metodologia-de-investigacion-social-interdisciplinaria-inicio\/admision\/\" \/>\n<meta property=\"og:site_name\" content=\"Direcci\u00f3n de Postgrado\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-22T20:38:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uoh.cl\/postgrado\/magister-en-metodologia-de-investigacion-social-interdisciplinaria-inicio\/admision\/\",\"url\":\"https:\/\/www.uoh.cl\/postgrado\/magister-en-metodologia-de-investigacion-social-interdisciplinaria-inicio\/admision\/\",\"name\":\"Mag\u00edster en Metodolog\u00eda de Investigaci\u00f3n Social Interdisciplinaria Admisi\u00f3n - Direcci\u00f3n de Postgrado\",\"isPartOf\":{\"@id\":\"https:\/\/www.uoh.cl\/postgrado\/#website\"},\"datePublished\":\"2025-09-30T18:59:19+00:00\",\"dateModified\":\"2025-12-22T20:38:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.uoh.cl\/postgrado\/magister-en-metodologia-de-investigacion-social-interdisciplinaria-inicio\/admision\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uoh.cl\/postgrado\/magister-en-metodologia-de-investigacion-social-interdisciplinaria-inicio\/admision\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.uoh.cl\/postgrado\/magister-en-metodologia-de-investigacion-social-interdisciplinaria-inicio\/admision\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.uoh.cl\/postgrado\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mag\u00edster en Metodolog\u00eda de Investigaci\u00f3n Social Interdisciplinaria Inicio\",\"item\":\"https:\/\/www.uoh.cl\/postgrado\/magister-en-metodologia-de-investigacion-social-interdisciplinaria-inicio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mag\u00edster en Metodolog\u00eda de Investigaci\u00f3n Social Interdisciplinaria Admisi\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uoh.cl\/postgrado\/#website\",\"url\":\"https:\/\/www.uoh.cl\/postgrado\/\",\"name\":\"Direcci\u00f3n de Postgrado\",\"description\":\"Otro sitio de Sitios de Universidad O'higgins\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uoh.cl\/postgrado\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mag\u00edster en Metodolog\u00eda de Investigaci\u00f3n Social Interdisciplinaria Admisi\u00f3n - Direcci\u00f3n de Postgrado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uoh.cl\/postgrado\/magister-en-metodologia-de-investigacion-social-interdisciplinaria-inicio\/admision\/","og_locale":"es_ES","og_type":"article","og_title":"Mag\u00edster en Metodolog\u00eda de Investigaci\u00f3n Social Interdisciplinaria Admisi\u00f3n - Direcci\u00f3n de Postgrado","og_description":"[vc_row][vc_column][\/vc_column][\/vc_row][vc_section el_class=&#8221;circle&#8211;pattern pb-4&#8243; css=&#8221;.vc_custom_1759259942291{padding-top: 3rem !important;}&#8221; el_id=&#8221;requisitos&#8221;][vc_row el_class=&#8221;container mx-auto align-items-center&#8221;][vc_column width=&#8221;1\/2&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][\/vc_column][\/vc_row][vc_row el_class=&#8221;container mx-auto align-items-start&#8221;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1693338597452{padding-right: 2rem !important;}&#8221;][vc_tta_accordion style=&#8221;modern&#8221; active_section=&#8221;1&#8243; collapsible_all=&#8221;true&#8221;][vc_tta_section i_position=&#8221;right&#8221; i_icon_fontawesome=&#8221;fas fa-pencil-alt&#8221; add_icon=&#8221;true&#8221; title=&#8221;Requisitos de postulaci\u00f3n&#8221; tab_id=&#8221;1692372173513-bb958d50-bdb4&#8243;][vc_column_text css=&#8221;&#8221;]Contar con el grado acad\u00e9mico de Licenciatura en Ciencias Sociales o disciplinas afines, conferido por universidades nacionales o extranjeras. Para t\u00edtulos o grados extranjeros se [&hellip;]","og_url":"https:\/\/www.uoh.cl\/postgrado\/magister-en-metodologia-de-investigacion-social-interdisciplinaria-inicio\/admision\/","og_site_name":"Direcci\u00f3n de Postgrado","article_modified_time":"2025-12-22T20:38:21+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo estimado de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/postgrado\/magister-en-metodologia-de-investigacion-social-interdisciplinaria-inicio\/admision\/","url":"https:\/\/www.uoh.cl\/postgrado\/magister-en-metodologia-de-investigacion-social-interdisciplinaria-inicio\/admision\/","name":"Mag\u00edster en Metodolog\u00eda de Investigaci\u00f3n Social Interdisciplinaria Admisi\u00f3n - Direcci\u00f3n de Postgrado","isPartOf":{"@id":"https:\/\/www.uoh.cl\/postgrado\/#website"},"datePublished":"2025-09-30T18:59:19+00:00","dateModified":"2025-12-22T20:38:21+00:00","breadcrumb":{"@id":"https:\/\/www.uoh.cl\/postgrado\/magister-en-metodologia-de-investigacion-social-interdisciplinaria-inicio\/admision\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/postgrado\/magister-en-metodologia-de-investigacion-social-interdisciplinaria-inicio\/admision\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.uoh.cl\/postgrado\/magister-en-metodologia-de-investigacion-social-interdisciplinaria-inicio\/admision\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.uoh.cl\/postgrado\/"},{"@type":"ListItem","position":2,"name":"Mag\u00edster en Metodolog\u00eda de Investigaci\u00f3n Social Interdisciplinaria Inicio","item":"https:\/\/www.uoh.cl\/postgrado\/magister-en-metodologia-de-investigacion-social-interdisciplinaria-inicio\/"},{"@type":"ListItem","position":3,"name":"Mag\u00edster en Metodolog\u00eda de Investigaci\u00f3n Social Interdisciplinaria Admisi\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/postgrado\/#website","url":"https:\/\/www.uoh.cl\/postgrado\/","name":"Direcci\u00f3n de Postgrado","description":"Otro sitio de Sitios de Universidad O'higgins","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/postgrado\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/postgrado\/wp-json\/wp\/v2\/pages\/2810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/postgrado\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.uoh.cl\/postgrado\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/postgrado\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/postgrado\/wp-json\/wp\/v2\/comments?post=2810"}],"version-history":[{"count":26,"href":"https:\/\/www.uoh.cl\/postgrado\/wp-json\/wp\/v2\/pages\/2810\/revisions"}],"predecessor-version":[{"id":3366,"href":"https:\/\/www.uoh.cl\/postgrado\/wp-json\/wp\/v2\/pages\/2810\/revisions\/3366"}],"up":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/postgrado\/wp-json\/wp\/v2\/pages\/2794"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/postgrado\/wp-json\/wp\/v2\/media?parent=2810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}