
{"id":6677,"date":"2023-01-12T14:49:15","date_gmt":"2023-01-12T17:49:15","guid":{"rendered":"https:\/\/www.uoh.cl\/investigacion\/rectores-de-las-universidades-publicas-hacen-un-balance-del-2022\/"},"modified":"2023-01-12T16:46:36","modified_gmt":"2023-01-12T19:46:36","slug":"rectores-de-las-universidades-publicas-hacen-un-balance-del-2022","status":"publish","type":"post","link":"https:\/\/www.uoh.cl\/investigacion\/rectores-de-las-universidades-publicas-hacen-un-balance-del-2022\/","title":{"rendered":"Rectores de las Universidades P\u00fablicas hacen un balance del 2022"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center text-right circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row][vc_column]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/investigacion\"><span itemprop=\"name\">Investigaci\u00f3n<\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/investigacion\/noticias\/\"><span itemprop=\"name\">Noticias<\/span><\/a><meta itemprop=\"position\" content=\"3\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Rectores de las Universidades P\u00fablicas hacen un balance del 2022 <\/span><meta itemprop=\"position\" content=\"4\" \/><\/ol><\/div><ul class=\"p-0 list-style-none d-inline-block\"><li class=\"p-0\"><a href=https:\/\/www.uoh.cl\/investigacion\/category\/institucional\/ class=\"px-1 py-2\">Institucional<\/a><\/li><\/ul><div class=\"date_publish_post\"> \u25cf Jue 12 de Enero 2023<\/div><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block title--decorator  big\">Rectores de las Universidades P\u00fablicas hacen un balance del 2022<\/h1><\/div>[vc_row_inner el_class=&#8221;border-separator m-0&#8243;][vc_column_inner width=&#8221;2\/3&#8243;]<div class=\"author_wp_class\"> Escrito por <span>Universidad de O'Higgins<\/span><\/div>[\/vc_column_inner][vc_column_inner el_class=&#8221;align-items-end-publish&#8221; width=&#8221;1\/3&#8243;]<div class=\"uoh_social_network_component uoh_row col-12 justify-content-end m-0 p-0\"> <div class=\"icon__facebook-share-button\">\n                       <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.uoh.cl\/investigacion\/rectores-de-las-universidades-publicas-hacen-un-balance-del-2022\/\" target=\"_blank\"> <div class=\"icon__facebook-svg\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22.4px\" height=\"48.3px\" viewBox=\"0 0 22.4 48.3\" style=\"overflow:visible;enable-background:new 0 0 22.4 48.3;\" xml:space=\"preserve\">\n                <defs>\n                <\/defs>\n                <path class=\"st0\" d=\"M22.4,15.6h-7.6v-5c0-1.9,1.2-2.3,2.1-2.3c0.9,0,5.4,0,5.4,0V0l-7.4,0C6.6,0,4.8,6.2,4.8,10.1v5.5H0v8.5h4.8\n                    c0,10.9,0,24.1,0,24.1h10c0,0,0-13.3,0-24.1h6.8L22.4,15.6z\"><\/path>\n                <\/svg><\/a><\/div>\n                    <\/div><div class=\"icon__twitter-share-button\">\n                        <div class=\"icon__twitter-svg\"><a target=\"_blank\" href=\"http:\/\/twitter.com\/share?url=https:\/\/www.uoh.cl\/investigacion\/rectores-de-las-universidades-publicas-hacen-un-balance-del-2022\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/a><\/div>\n                        <\/div><div class=\"icon__linkedin-share-button\">\n                        <div class=\"icon__linkedin-svg\">\n                        <a target=\"__blank\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.uoh.cl\/investigacion\/rectores-de-las-universidades-publicas-hacen-un-balance-del-2022\/\"><svg enable-background=\"new 0 0 100 100\" height=\"100px\" id=\"Layer_1\" version=\"1.1\" viewBox=\"0 0 100 100\" width=\"100px\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><circle cx=\"50\" cy=\"50\" fill=\"#ccc\" r=\"45\"\/><g id=\"LinkedIn_1_\"><rect fill=\"#FFFFFF\" height=\"24.361\" width=\"7.69\" x=\"31.271\" y=\"43.569\"\/><path d=\"M59.968,43.334c-4.406,0-7.165,2.387-7.677,4.058v-3.823h-8.636c0.109,2.03,0,24.361,0,24.361h8.636    V54.748c0-0.733-0.034-1.465,0.19-1.991c0.594-1.464,1.869-2.985,4.162-2.985c2.998,0,4.361,2.253,4.361,5.552V67.93h8.721V54.384    C69.726,46.839,65.432,43.334,59.968,43.334z\" fill=\"#FFFFFF\"\/><path d=\"M34.973,32.069c-2.839,0-4.696,1.823-4.696,4.229c0,2.361,1.804,4.224,4.589,4.224h0.054    c2.891,0,4.69-1.869,4.69-4.229C39.555,33.888,37.81,32.069,34.973,32.069z\" fill=\"#FFFFFF\"\/><\/g><\/g><\/svg><\/a><\/div>\n\n            <\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_single_image image=&#8221;16436&#8243; img_size=&#8221;full&#8221;][vc_column_text]\u00a0[\/vc_column_text][vc_column_text]<em>Entre los puntos que guiar\u00e1n el accionar de las universidades p\u00fablicas est\u00e1 la implementaci\u00f3n de los nuevos estatutos, la ley que regula la violencia de g\u00e9nero en las universidades y el trabajo por mejorar la salud mental de estudiantes y funcionarios.<\/em><\/p>\n<p>[\/vc_column_text][vc_column_text]\u00a0[\/vc_column_text][vc_column_text]En la reuni\u00f3n mensual del Consorcio de Universidades del Estado (CUECH) realizada en la Universidad de Tarapac\u00e1, las y los rectores de las universidades p\u00fablicas analizaron los principales avances del reciente a\u00f1o y proyectaron las l\u00edneas de trabajo para los pr\u00f3ximos meses.<\/p>\n<p>Durante la ma\u00f1ana del mi\u00e9rcoles 11 de enero, las 18 universidades estatales realizaron un balance del 2022. En esta Instancia, el presidente del CUECH, Osvaldo Corrales, destac\u00f3 logros program\u00e1ticos y tambi\u00e9n avances en materia presupuestaria que permitir\u00e1n hacer frente a la situaci\u00f3n financiera de este periodo y que incluyen la modificaci\u00f3n del art\u00edculo 48 y la utilizaci\u00f3n de una parte de los excedentes del Fondo Solidario.<\/p>\n<p>Adem\u00e1s, se discuti\u00f3 sobre los desaf\u00edos de los planteles para este 2023 que proyecta una agenda de trabajo para avanzar en el fortalecimiento de la educaci\u00f3n superior p\u00fablica:\u00a0 \u201cTenemos acordadas dos mesas; Una mesa tripartita con los gremios, con el Gobierno y rectores; y una mesa bipartita con la Subsecretar\u00eda de Educaci\u00f3n Superior para abordar el gran tema que nos preocupa que es el aporte de los montos basales con los que se va a financiar la educaci\u00f3n p\u00fablica\u201d, se\u00f1al\u00f3 el tambi\u00e9n rector de la Universidad de Valpara\u00edso.<\/p>\n<p>En este sentido dentro de las l\u00edneas de trabajo para este a\u00f1o, tambi\u00e9n est\u00e1 la discusi\u00f3n sobre la ampliaci\u00f3n de la matricula que actualmente llega solo al 16% del total nacional. El rector Osvaldo Corrales, indic\u00f3 al respecto que \u201ctenemos un trabajo con el Gobierno para que la educaci\u00f3n superior publica represente un porcentaje mayor de la matricula y ah\u00ed hay un desaf\u00edo para nuestras casas de estudio, sobre todo, para hacernos cargo de algunas de las prioridades que nuestro pa\u00eds tiene en materia de capital humano\u201d.<\/p>\n<p>Entre otros puntos que guiar\u00e1n el accionar de las universidades p\u00fablicas, est\u00e1 la implementaci\u00f3n de los nuevos estatutos, la ley que regula la violencia de g\u00e9nero en las universidades y el trabajo por mejorar la salud mental de estudiantes y funcionarios.<\/p>\n<p>Finalmente, durante la jornada se abordaron los resultados y proyecciones del Programa de Movilidad Nacional que consolida un espacio de formaci\u00f3n com\u00fan para todas las universidades estatales con la oportunidad de que estudiantes realicen programas en modalidad virtual y presencial a lo largo de Chile.<\/p>\n<p>Leonor Armanet, integrante del Directorio de la Red de Pregrado del CUECH, indic\u00f3 que durante este a\u00f1o se busca potenciar, y profundizar la movilidad estudiantil: \u201cVemos la posibilidad de ampliar las opciones de conocimiento y de formaci\u00f3n de nuestros estudiantes con foco territorial\u201d, destacando que este programa representa una oportunidad para el Sistema de Universidades del Estado.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/5&#8243;][\/vc_column][vc_column width=&#8221;1\/5&#8243;][\/vc_column][vc_column width=&#8221;1\/5&#8243;][\/vc_column][vc_column width=&#8221;1\/5&#8243;][\/vc_column][vc_column width=&#8221;1\/5&#8243;][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650255686594{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center text-right p-md-0 pt-5 pb-5&#8243;][vc_column el_class=&#8221;pb-5&#8243;][vc_row_inner el_class=&#8221;pb-5&#8243;][vc_column_inner]<div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0\"><h2 class=\"title title--decorator title--ms d-inline-block\">Te Recomendamos<\/h2><\/div><\/div><div class=\"content-holder\"><div class=\"row  swipper-news-list not--activate-hack \"><div class=\"row -wrapper\"><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/investigacion\/category\/observatorio-laboral\/\">\n                                        Observatorio Laboral<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2026\/05\/Observatorio-Laboral-1-scaled.jpg\" alt=\"Desocupaci\u00f3n se mantiene estable y brecha de g\u00e9nero se cierra por primera vez\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/1707;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Lunes 11, Mayo<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/investigacion\/desocupacion-se-mantiene-estable-y-brecha-de-genero-se-cierra-por-primera-vez\/\">\n                                    <h3 class=\"small-space\">Desocupaci\u00f3n se mantiene estable y brecha de g\u00e9nero se cierra por primera vez<\/h3><\/a>\n\n                                    <p>Mientras que la desocupaci\u00f3n en los hombres subi\u00f3 2,6 puntos, la de las mujeres baj\u00f3 3,6 puntos.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/investigacion\/desocupacion-se-mantiene-estable-y-brecha-de-genero-se-cierra-por-primera-vez\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/investigacion\/category\/investigacion\/\">\n                                        Investigaci\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2026\/04\/FWIS2026-web-op.jpg\" alt=\"Comienza proceso de postulaciones al Premio For Women in Science 2026\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/444;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Jueves 30, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/investigacion\/comienza-proceso-de-postulaciones-al-premio-for-women-in-science-2026\/\">\n                                    <h3 class=\"small-space\">Comienza proceso de postulaciones al Premio For Women in Science 2026<\/h3><\/a>\n\n                                    <p>La convocatoria, abierta entre el 22 de abril y el 28 de mayo de 2026, busca impulsar la trayectoria y aporte cient\u00edfico de investigadoras chilenas.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/investigacion\/comienza-proceso-de-postulaciones-al-premio-for-women-in-science-2026\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/investigacion\/category\/investigacion\/\">\n                                        Investigaci\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2026\/04\/Dia-de-la-Propiedad-Intelectual.jpg\" alt=\"UOH conmemora D\u00eda Mundial de la Propiedad Intelectual destacando avances en protecci\u00f3n\" style=\"--smush-placeholder-width: 2419px; --smush-placeholder-aspect-ratio: 2419\/1609;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Jueves 30, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/investigacion\/uoh-conmemora-dia-mundial-de-la-propiedad-intelectual-destacando-avances-en-proteccion\/\">\n                                    <h3 class=\"small-space\">UOH conmemora D\u00eda Mundial de la Propiedad Intelectual destacando avances en protecci\u00f3n<\/h3><\/a>\n\n                                    <p>La Direcci\u00f3n de Transferencia e Innovaci\u00f3n ha apoyado la protecci\u00f3n de 21 resultados de investigaci\u00f3n, concretado 11 solicitudes de patente, 12 registros de derechos de autor y 1 marca comercial.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/investigacion\/uoh-conmemora-dia-mundial-de-la-propiedad-intelectual-destacando-avances-en-proteccion\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pagination justify-content-center my-5\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/posts\/6677\/\/page\/2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/posts\/6677\/\/page\/3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/posts\/6677\/\/page\/132\">132<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/posts\/6677\/\/page\/2\"><div class=\"icon-pagination-next\"> <?xml version=\"1.0\" ?><svg viewBox=\"0 0 96 96\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><title\/><path d=\"M39.3756,48.0022l30.47-25.39a6.0035,6.0035,0,0,0-7.6878-9.223L26.1563,43.3906a6.0092,6.0092,0,0,0,0,9.2231L62.1578,82.615a6.0035,6.0035,0,0,0,7.6878-9.2231Z\"\/><\/svg> <\/div><\/a><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Entre los puntos que guiar\u00e1n el accionar de las universidades p\u00fablicas en 2023 est\u00e1 la implementaci\u00f3n de los nuevos estatutos, la ley que regula la violencia de g\u00e9nero en las universidades y el trabajo por mejorar la salud mental de estudiantes y funcionarios.<\/p>\n","protected":false},"author":34,"featured_media":6681,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[47],"tags":[],"class_list":["post-6677","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucional"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rectores de las Universidades P\u00fablicas hacen un balance del 2022 - Investigaci\u00f3n<\/title>\n<meta name=\"description\" content=\"Entre los puntos que guiar\u00e1n el accionar de las universidades p\u00fablicas est\u00e1 la implementaci\u00f3n de los nuevos estatutos, la ley que regula la violencia de g\u00e9nero en las universidades y el trabajo por mejorar la salud mental de estudiantes y funcionarios.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rectores de las Universidades P\u00fablicas hacen un balance del 2022 - Investigaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Entre los puntos que guiar\u00e1n el accionar de las universidades p\u00fablicas est\u00e1 la implementaci\u00f3n de los nuevos estatutos, la ley que regula la violencia de g\u00e9nero en las universidades y el trabajo por mejorar la salud mental de estudiantes y funcionarios.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/investigacion\/rectores-de-las-universidades-publicas-hacen-un-balance-del-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Investigaci\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-12T17:49:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-12T19:46:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2023\/01\/CUECH-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Universidad de O&#039;Higgins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Universidad de O&#039;Higgins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/rectores-de-las-universidades-publicas-hacen-un-balance-del-2022\/\",\"url\":\"https:\/\/www.uoh.cl\/investigacion\/rectores-de-las-universidades-publicas-hacen-un-balance-del-2022\/\",\"name\":\"Rectores de las Universidades P\u00fablicas hacen un balance del 2022 - Investigaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/rectores-de-las-universidades-publicas-hacen-un-balance-del-2022\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/rectores-de-las-universidades-publicas-hacen-un-balance-del-2022\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2023\/01\/CUECH-4.jpg\",\"datePublished\":\"2023-01-12T17:49:15+00:00\",\"dateModified\":\"2023-01-12T19:46:36+00:00\",\"author\":{\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"description\":\"Entre los puntos que guiar\u00e1n el accionar de las universidades p\u00fablicas est\u00e1 la implementaci\u00f3n de los nuevos estatutos, la ley que regula la violencia de g\u00e9nero en las universidades y el trabajo por mejorar la salud mental de estudiantes y funcionarios.\",\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uoh.cl\/investigacion\/rectores-de-las-universidades-publicas-hacen-un-balance-del-2022\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/rectores-de-las-universidades-publicas-hacen-un-balance-del-2022\/#primaryimage\",\"url\":\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2023\/01\/CUECH-4.jpg\",\"contentUrl\":\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2023\/01\/CUECH-4.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/#website\",\"url\":\"https:\/\/www.uoh.cl\/investigacion\/\",\"name\":\"Investigaci\u00f3n\",\"description\":\"Sitio web de investigaci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uoh.cl\/investigacion\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\",\"name\":\"Universidad de O'Higgins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"caption\":\"Universidad de O'Higgins\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rectores de las Universidades P\u00fablicas hacen un balance del 2022 - Investigaci\u00f3n","description":"Entre los puntos que guiar\u00e1n el accionar de las universidades p\u00fablicas est\u00e1 la implementaci\u00f3n de los nuevos estatutos, la ley que regula la violencia de g\u00e9nero en las universidades y el trabajo por mejorar la salud mental de estudiantes y funcionarios.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Rectores de las Universidades P\u00fablicas hacen un balance del 2022 - Investigaci\u00f3n","og_description":"Entre los puntos que guiar\u00e1n el accionar de las universidades p\u00fablicas est\u00e1 la implementaci\u00f3n de los nuevos estatutos, la ley que regula la violencia de g\u00e9nero en las universidades y el trabajo por mejorar la salud mental de estudiantes y funcionarios.","og_url":"https:\/\/www.uoh.cl\/investigacion\/rectores-de-las-universidades-publicas-hacen-un-balance-del-2022\/","og_site_name":"Investigaci\u00f3n","article_published_time":"2023-01-12T17:49:15+00:00","article_modified_time":"2023-01-12T19:46:36+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2023\/01\/CUECH-4.jpg","type":"image\/jpeg"}],"author":"Universidad de O'Higgins","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Universidad de O'Higgins","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/investigacion\/rectores-de-las-universidades-publicas-hacen-un-balance-del-2022\/","url":"https:\/\/www.uoh.cl\/investigacion\/rectores-de-las-universidades-publicas-hacen-un-balance-del-2022\/","name":"Rectores de las Universidades P\u00fablicas hacen un balance del 2022 - Investigaci\u00f3n","isPartOf":{"@id":"https:\/\/www.uoh.cl\/investigacion\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uoh.cl\/investigacion\/rectores-de-las-universidades-publicas-hacen-un-balance-del-2022\/#primaryimage"},"image":{"@id":"https:\/\/www.uoh.cl\/investigacion\/rectores-de-las-universidades-publicas-hacen-un-balance-del-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2023\/01\/CUECH-4.jpg","datePublished":"2023-01-12T17:49:15+00:00","dateModified":"2023-01-12T19:46:36+00:00","author":{"@id":"https:\/\/www.uoh.cl\/investigacion\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"description":"Entre los puntos que guiar\u00e1n el accionar de las universidades p\u00fablicas est\u00e1 la implementaci\u00f3n de los nuevos estatutos, la ley que regula la violencia de g\u00e9nero en las universidades y el trabajo por mejorar la salud mental de estudiantes y funcionarios.","inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/investigacion\/rectores-de-las-universidades-publicas-hacen-un-balance-del-2022\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/investigacion\/rectores-de-las-universidades-publicas-hacen-un-balance-del-2022\/#primaryimage","url":"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2023\/01\/CUECH-4.jpg","contentUrl":"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2023\/01\/CUECH-4.jpg","width":1000,"height":1000},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/investigacion\/#website","url":"https:\/\/www.uoh.cl\/investigacion\/","name":"Investigaci\u00f3n","description":"Sitio web de investigaci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/investigacion\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/www.uoh.cl\/investigacion\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f","name":"Universidad de O'Higgins","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/investigacion\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","caption":"Universidad de O'Higgins"}}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/posts\/6677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/comments?post=6677"}],"version-history":[{"count":1,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/posts\/6677\/revisions"}],"predecessor-version":[{"id":6680,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/posts\/6677\/revisions\/6680"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/media\/6681"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/media?parent=6677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/categories?post=6677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/tags?post=6677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}