
{"id":2861,"date":"2022-07-04T14:06:52","date_gmt":"2022-07-04T17:06:52","guid":{"rendered":"https:\/\/www.uoh.cl\/investigacion\/escuela-de-ciencias-sociales-lanza-campana-informativa-de-cara-al-plebiscito-constitucional\/"},"modified":"2022-07-04T14:06:52","modified_gmt":"2022-07-04T17:06:52","slug":"escuela-de-ciencias-sociales-lanza-campana-informativa-de-cara-al-plebiscito-constitucional","status":"publish","type":"post","link":"https:\/\/www.uoh.cl\/investigacion\/escuela-de-ciencias-sociales-lanza-campana-informativa-de-cara-al-plebiscito-constitucional\/","title":{"rendered":"#TuVotoImporta: Escuela de Ciencias Sociales lanza campa\u00f1a informativa de cara al plebiscito constitucional"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center text-right circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row][vc_column]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/investigacion\"><span itemprop=\"name\">Investigaci\u00f3n<\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/investigacion\/noticias\/\"><span itemprop=\"name\">Noticias<\/span><\/a><meta itemprop=\"position\" content=\"3\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">#TuVotoImporta: Escuela de Ciencias Sociales lanza campa\u00f1a informativa de cara <\/span><meta itemprop=\"position\" content=\"4\" \/><\/ol><\/div><ul class=\"p-0 list-style-none d-inline-block\"><li class=\"p-0\"><a href=https:\/\/www.uoh.cl\/investigacion\/category\/institucional\/ class=\"px-1 py-2\">Institucional<\/a><\/li><\/ul><div class=\"date_publish_post\"> \u25cf Lun 04 de Julio 2022<\/div><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block title--decorator  big\">#TuVotoImporta: Escuela de Ciencias Sociales lanza campa\u00f1a informativa de cara al plebiscito constitucional<\/h1><\/div>[vc_row_inner el_class=&#8221;border-separator m-0&#8243;][vc_column_inner width=&#8221;2\/3&#8243;]<div class=\"author_wp_class\"> Escrito por <span>Universidad de O'Higgins<\/span><\/div>[\/vc_column_inner][vc_column_inner el_class=&#8221;align-items-end-publish&#8221; width=&#8221;1\/3&#8243;]<div class=\"uoh_social_network_component uoh_row col-12 justify-content-end m-0 p-0\"> <div class=\"icon__facebook-share-button\">\n                       <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.uoh.cl\/investigacion\/escuela-de-ciencias-sociales-lanza-campana-informativa-de-cara-al-plebiscito-constitucional\/\" target=\"_blank\"> <div class=\"icon__facebook-svg\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22.4px\" height=\"48.3px\" viewBox=\"0 0 22.4 48.3\" style=\"overflow:visible;enable-background:new 0 0 22.4 48.3;\" xml:space=\"preserve\">\n                <defs>\n                <\/defs>\n                <path class=\"st0\" d=\"M22.4,15.6h-7.6v-5c0-1.9,1.2-2.3,2.1-2.3c0.9,0,5.4,0,5.4,0V0l-7.4,0C6.6,0,4.8,6.2,4.8,10.1v5.5H0v8.5h4.8\n                    c0,10.9,0,24.1,0,24.1h10c0,0,0-13.3,0-24.1h6.8L22.4,15.6z\"><\/path>\n                <\/svg><\/a><\/div>\n                    <\/div><div class=\"icon__twitter-share-button\">\n                        <div class=\"icon__twitter-svg\"><a target=\"_blank\" href=\"http:\/\/twitter.com\/share?url=https:\/\/www.uoh.cl\/investigacion\/escuela-de-ciencias-sociales-lanza-campana-informativa-de-cara-al-plebiscito-constitucional\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/a><\/div>\n                        <\/div><div class=\"icon__linkedin-share-button\">\n                        <div class=\"icon__linkedin-svg\">\n                        <a target=\"__blank\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.uoh.cl\/investigacion\/escuela-de-ciencias-sociales-lanza-campana-informativa-de-cara-al-plebiscito-constitucional\/\"><svg enable-background=\"new 0 0 100 100\" height=\"100px\" id=\"Layer_1\" version=\"1.1\" viewBox=\"0 0 100 100\" width=\"100px\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><circle cx=\"50\" cy=\"50\" fill=\"#ccc\" r=\"45\"\/><g id=\"LinkedIn_1_\"><rect fill=\"#FFFFFF\" height=\"24.361\" width=\"7.69\" x=\"31.271\" y=\"43.569\"\/><path d=\"M59.968,43.334c-4.406,0-7.165,2.387-7.677,4.058v-3.823h-8.636c0.109,2.03,0,24.361,0,24.361h8.636    V54.748c0-0.733-0.034-1.465,0.19-1.991c0.594-1.464,1.869-2.985,4.162-2.985c2.998,0,4.361,2.253,4.361,5.552V67.93h8.721V54.384    C69.726,46.839,65.432,43.334,59.968,43.334z\" fill=\"#FFFFFF\"\/><path d=\"M34.973,32.069c-2.839,0-4.696,1.823-4.696,4.229c0,2.361,1.804,4.224,4.589,4.224h0.054    c2.891,0,4.69-1.869,4.69-4.229C39.555,33.888,37.81,32.069,34.973,32.069z\" fill=\"#FFFFFF\"\/><\/g><\/g><\/svg><\/a><\/div>\n\n            <\/div><\/div>[\/vc_column_inner][\/vc_row_inner]<div class=\"vc_single_image-wrapper vc_box_rounded  vc_box_border_grey\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2022\/07\/Nota-Votacion.jpg\" class=\"attachment-large size-large wp-post-image lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" \/><\/div>[vc_column_text]<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[\/vc_column_text][vc_column_text]<em>V<\/em><em>ideos y boletines semanales preparados por profesionales de derecho y administraci\u00f3n p\u00fablica de la UOH comunican temas fundamentales de la nueva Constituci\u00f3n para as\u00ed aportar a la responsabilidad ciudadana de ejercer un voto informado.<\/em>[\/vc_column_text][vc_column_text]<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[\/vc_column_text][vc_column_text]Tras casi 365 d\u00edas de trabajo de las y los convencionales, este lunes se realiz\u00f3 la entrega oficial de la propuesta de una nueva Constituci\u00f3n para Chile. Ahora, el 4 de septiembre pr\u00f3ximo, todos\/as quienes est\u00e1n habilitados para votar decidir\u00e1n la aprobaci\u00f3n o el rechazo de la nueva Carta Magna.<\/p>\n<p>&#8220;Como Escuela de Ciencias Sociales tenemos el deber de contribuir al debate p\u00fablico que se ha generado en torno a la creaci\u00f3n de una nueva Constituci\u00f3n. Es por ello, que desde el a\u00f1o 2020 hemos organizado distintas actividades como el Ciclo de charlas y conversatorios con acad\u00e9micos\/as, la creaci\u00f3n de una Escuela Constituyente de verano, adem\u00e1s de generar espacios de conversaci\u00f3n con los candidatos a convencionales. Esta campa\u00f1a sigue la l\u00ednea trazada y responde al rol p\u00fablico que tenemos como Universidad&#8221;, afirm\u00f3 el jefe de la carrera de Derecho, Marcelo Acu\u00f1a.<\/p>\n<p>En tanto, el jefe de carrera de Administraci\u00f3n P\u00fablica, Juan Pablo Araya se\u00f1al\u00f3 que \u201ccon el prop\u00f3sito de dar a conocer los aspectos m\u00e1s importantes de la propuesta emanada por la Convenci\u00f3n Constitucional, estaremos publicando un bolet\u00edn que sintetiza las tem\u00e1ticas m\u00e1s importantes y las dimensiones en las que fueron tratadas en la propuesta de texto constitucional. Adem\u00e1s, a trav\u00e9s de las plataformas digitales de la Universidad se estar\u00e1n entregando la informaci\u00f3n clave para cumplir con nuestro deber ciudadano votando informadamente&#8221;.[\/vc_column_text][vc_column_text]<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650226078643{background-color: #ffffff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center text-right p-md-0 pt-5 pb-5&#8243;][vc_column el_class=&#8221;pb-5&#8243;][vc_row_inner el_class=&#8221;pb-5&#8243;][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;2\/3&#8243;][vc_column_text el_class=&#8221;mt-3&#8243;][\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650255686594{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center text-right p-md-0 pt-5 pb-5&#8243;][vc_column el_class=&#8221;pb-5&#8243;][vc_row_inner el_class=&#8221;pb-5&#8243;][vc_column_inner]<div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0\"><h2 class=\"title title--decorator title--ms d-inline-block\">Te Recomendamos<\/h2><\/div><\/div><div class=\"content-holder\"><div class=\"row  swipper-news-list not--activate-hack \"><div class=\"row -wrapper\"><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/investigacion\/category\/observatorio-laboral\/\">\n                                        Observatorio Laboral<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2026\/05\/Observatorio-Laboral-1-scaled.jpg\" alt=\"Desocupaci\u00f3n se mantiene estable y brecha de g\u00e9nero se cierra por primera vez\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/1707;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Lunes 11, Mayo<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/investigacion\/desocupacion-se-mantiene-estable-y-brecha-de-genero-se-cierra-por-primera-vez\/\">\n                                    <h3 class=\"small-space\">Desocupaci\u00f3n se mantiene estable y brecha de g\u00e9nero se cierra por primera vez<\/h3><\/a>\n\n                                    <p>Mientras que la desocupaci\u00f3n en los hombres subi\u00f3 2,6 puntos, la de las mujeres baj\u00f3 3,6 puntos.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/investigacion\/desocupacion-se-mantiene-estable-y-brecha-de-genero-se-cierra-por-primera-vez\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/investigacion\/category\/investigacion\/\">\n                                        Investigaci\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2026\/04\/FWIS2026-web-op.jpg\" alt=\"Comienza proceso de postulaciones al Premio For Women in Science 2026\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/444;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Jueves 30, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/investigacion\/comienza-proceso-de-postulaciones-al-premio-for-women-in-science-2026\/\">\n                                    <h3 class=\"small-space\">Comienza proceso de postulaciones al Premio For Women in Science 2026<\/h3><\/a>\n\n                                    <p>La convocatoria, abierta entre el 22 de abril y el 28 de mayo de 2026, busca impulsar la trayectoria y aporte cient\u00edfico de investigadoras chilenas.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/investigacion\/comienza-proceso-de-postulaciones-al-premio-for-women-in-science-2026\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/investigacion\/category\/investigacion\/\">\n                                        Investigaci\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2026\/04\/Dia-de-la-Propiedad-Intelectual.jpg\" alt=\"UOH conmemora D\u00eda Mundial de la Propiedad Intelectual destacando avances en protecci\u00f3n\" style=\"--smush-placeholder-width: 2419px; --smush-placeholder-aspect-ratio: 2419\/1609;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Jueves 30, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/investigacion\/uoh-conmemora-dia-mundial-de-la-propiedad-intelectual-destacando-avances-en-proteccion\/\">\n                                    <h3 class=\"small-space\">UOH conmemora D\u00eda Mundial de la Propiedad Intelectual destacando avances en protecci\u00f3n<\/h3><\/a>\n\n                                    <p>La Direcci\u00f3n de Transferencia e Innovaci\u00f3n ha apoyado la protecci\u00f3n de 21 resultados de investigaci\u00f3n, concretado 11 solicitudes de patente, 12 registros de derechos de autor y 1 marca comercial.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/investigacion\/uoh-conmemora-dia-mundial-de-la-propiedad-intelectual-destacando-avances-en-proteccion\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pagination justify-content-center my-5\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/posts\/2861\/\/page\/2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/posts\/2861\/\/page\/3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/posts\/2861\/\/page\/132\">132<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/posts\/2861\/\/page\/2\"><div class=\"icon-pagination-next\"> <?xml version=\"1.0\" ?><svg viewBox=\"0 0 96 96\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><title\/><path d=\"M39.3756,48.0022l30.47-25.39a6.0035,6.0035,0,0,0-7.6878-9.223L26.1563,43.3906a6.0092,6.0092,0,0,0,0,9.2231L62.1578,82.615a6.0035,6.0035,0,0,0,7.6878-9.2231Z\"\/><\/svg> <\/div><\/a><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Videos y boletines semanales preparados por profesionales de derecho y administraci\u00f3n p\u00fablica de la UOH comunican temas fundamentales de la nueva Constituci\u00f3n para as\u00ed aportar a la responsabilidad ciudadana de ejercer un voto informado.<\/p>\n","protected":false},"author":34,"featured_media":2862,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[47],"tags":[],"class_list":["post-2861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucional"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>#TuVotoImporta: Escuela de Ciencias Sociales lanza campa\u00f1a informativa de cara al plebiscito constitucional - Investigaci\u00f3n<\/title>\n<meta name=\"description\" content=\"Videos y boletines semanales preparados por profesionales de derecho y administraci\u00f3n p\u00fablica de la UOH comunican temas fundamentales de la nueva Constituci\u00f3n para as\u00ed aportar a la responsabilidad ciudadana de ejercer un voto informado.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#TuVotoImporta: Escuela de Ciencias Sociales lanza campa\u00f1a informativa de cara al plebiscito constitucional - Investigaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Videos y boletines semanales preparados por profesionales de derecho y administraci\u00f3n p\u00fablica de la UOH comunican temas fundamentales de la nueva Constituci\u00f3n para as\u00ed aportar a la responsabilidad ciudadana de ejercer un voto informado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/investigacion\/escuela-de-ciencias-sociales-lanza-campana-informativa-de-cara-al-plebiscito-constitucional\/\" \/>\n<meta property=\"og:site_name\" content=\"Investigaci\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-04T17:06:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2022\/07\/Nota-Votacion.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Universidad de O&#039;Higgins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Universidad de O&#039;Higgins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/escuela-de-ciencias-sociales-lanza-campana-informativa-de-cara-al-plebiscito-constitucional\/\",\"url\":\"https:\/\/www.uoh.cl\/investigacion\/escuela-de-ciencias-sociales-lanza-campana-informativa-de-cara-al-plebiscito-constitucional\/\",\"name\":\"#TuVotoImporta: Escuela de Ciencias Sociales lanza campa\u00f1a informativa de cara al plebiscito constitucional - Investigaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/escuela-de-ciencias-sociales-lanza-campana-informativa-de-cara-al-plebiscito-constitucional\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/escuela-de-ciencias-sociales-lanza-campana-informativa-de-cara-al-plebiscito-constitucional\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2022\/07\/Nota-Votacion.jpg\",\"datePublished\":\"2022-07-04T17:06:52+00:00\",\"author\":{\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"description\":\"Videos y boletines semanales preparados por profesionales de derecho y administraci\u00f3n p\u00fablica de la UOH comunican temas fundamentales de la nueva Constituci\u00f3n para as\u00ed aportar a la responsabilidad ciudadana de ejercer un voto informado.\",\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uoh.cl\/investigacion\/escuela-de-ciencias-sociales-lanza-campana-informativa-de-cara-al-plebiscito-constitucional\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/escuela-de-ciencias-sociales-lanza-campana-informativa-de-cara-al-plebiscito-constitucional\/#primaryimage\",\"url\":\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2022\/07\/Nota-Votacion.jpg\",\"contentUrl\":\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2022\/07\/Nota-Votacion.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/#website\",\"url\":\"https:\/\/www.uoh.cl\/investigacion\/\",\"name\":\"Investigaci\u00f3n\",\"description\":\"Sitio web de investigaci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uoh.cl\/investigacion\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\",\"name\":\"Universidad de O'Higgins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"caption\":\"Universidad de O'Higgins\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#TuVotoImporta: Escuela de Ciencias Sociales lanza campa\u00f1a informativa de cara al plebiscito constitucional - Investigaci\u00f3n","description":"Videos y boletines semanales preparados por profesionales de derecho y administraci\u00f3n p\u00fablica de la UOH comunican temas fundamentales de la nueva Constituci\u00f3n para as\u00ed aportar a la responsabilidad ciudadana de ejercer un voto informado.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"#TuVotoImporta: Escuela de Ciencias Sociales lanza campa\u00f1a informativa de cara al plebiscito constitucional - Investigaci\u00f3n","og_description":"Videos y boletines semanales preparados por profesionales de derecho y administraci\u00f3n p\u00fablica de la UOH comunican temas fundamentales de la nueva Constituci\u00f3n para as\u00ed aportar a la responsabilidad ciudadana de ejercer un voto informado.","og_url":"https:\/\/www.uoh.cl\/investigacion\/escuela-de-ciencias-sociales-lanza-campana-informativa-de-cara-al-plebiscito-constitucional\/","og_site_name":"Investigaci\u00f3n","article_published_time":"2022-07-04T17:06:52+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2022\/07\/Nota-Votacion.jpg","type":"image\/jpeg"}],"author":"Universidad de O'Higgins","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Universidad de O'Higgins","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/investigacion\/escuela-de-ciencias-sociales-lanza-campana-informativa-de-cara-al-plebiscito-constitucional\/","url":"https:\/\/www.uoh.cl\/investigacion\/escuela-de-ciencias-sociales-lanza-campana-informativa-de-cara-al-plebiscito-constitucional\/","name":"#TuVotoImporta: Escuela de Ciencias Sociales lanza campa\u00f1a informativa de cara al plebiscito constitucional - Investigaci\u00f3n","isPartOf":{"@id":"https:\/\/www.uoh.cl\/investigacion\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uoh.cl\/investigacion\/escuela-de-ciencias-sociales-lanza-campana-informativa-de-cara-al-plebiscito-constitucional\/#primaryimage"},"image":{"@id":"https:\/\/www.uoh.cl\/investigacion\/escuela-de-ciencias-sociales-lanza-campana-informativa-de-cara-al-plebiscito-constitucional\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2022\/07\/Nota-Votacion.jpg","datePublished":"2022-07-04T17:06:52+00:00","author":{"@id":"https:\/\/www.uoh.cl\/investigacion\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"description":"Videos y boletines semanales preparados por profesionales de derecho y administraci\u00f3n p\u00fablica de la UOH comunican temas fundamentales de la nueva Constituci\u00f3n para as\u00ed aportar a la responsabilidad ciudadana de ejercer un voto informado.","inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/investigacion\/escuela-de-ciencias-sociales-lanza-campana-informativa-de-cara-al-plebiscito-constitucional\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/investigacion\/escuela-de-ciencias-sociales-lanza-campana-informativa-de-cara-al-plebiscito-constitucional\/#primaryimage","url":"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2022\/07\/Nota-Votacion.jpg","contentUrl":"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2022\/07\/Nota-Votacion.jpg","width":1500,"height":1000},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/investigacion\/#website","url":"https:\/\/www.uoh.cl\/investigacion\/","name":"Investigaci\u00f3n","description":"Sitio web de investigaci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/investigacion\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/www.uoh.cl\/investigacion\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f","name":"Universidad de O'Higgins","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/investigacion\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","caption":"Universidad de O'Higgins"}}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/posts\/2861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/comments?post=2861"}],"version-history":[{"count":0,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/posts\/2861\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/media\/2862"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/media?parent=2861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/categories?post=2861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/tags?post=2861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}