
{"id":10678,"date":"2024-07-26T13:00:14","date_gmt":"2024-07-26T16:00:14","guid":{"rendered":"https:\/\/www.uoh.cl\/investigacion\/realidad-y-necesidades-de-los-campesinos-en-el-chile-actual\/"},"modified":"2024-07-26T15:57:02","modified_gmt":"2024-07-26T18:57:02","slug":"realidad-y-necesidades-de-los-campesinos-en-el-chile-actual","status":"publish","type":"post","link":"https:\/\/www.uoh.cl\/investigacion\/realidad-y-necesidades-de-los-campesinos-en-el-chile-actual\/","title":{"rendered":"Realidad y necesidades campesinas en el Chile actual"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row][vc_column]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/investigacion\"><span itemprop=\"name\">Investigaci\u00f3n<\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/investigacion\/noticias\/\"><span itemprop=\"name\">Noticias<\/span><\/a><meta itemprop=\"position\" content=\"3\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Realidad y necesidades campesinas en el Chile actual <\/span><meta itemprop=\"position\" content=\"4\" \/><\/ol><\/div><ul class=\"p-0 list-style-none d-inline-block\"><li class=\"p-0\"><a href=https:\/\/www.uoh.cl\/investigacion\/category\/observatorio-laboral\/ class=\"px-1 py-2\">Observatorio Laboral<\/a><\/li><\/ul><div class=\"date_publish_post\"> \u25cf Vie 26 de Julio 2024<\/div><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block title--decorator  big\">Realidad y necesidades campesinas en el Chile actual<\/h1><\/div>[vc_row_inner el_class=&#8221;border-separator m-0&#8243;][vc_column_inner width=&#8221;2\/3&#8243;]<div class=\"author_wp_class\"> Escrito por <span>Universidad de O'Higgins<\/span><\/div>[\/vc_column_inner][vc_column_inner el_class=&#8221;align-items-end-publish&#8221; width=&#8221;1\/3&#8243;]<div class=\"uoh_social_network_component uoh_row col-12 justify-content-end m-0 p-0\"> <div class=\"icon__facebook-share-button\">\n                       <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.uoh.cl\/investigacion\/realidad-y-necesidades-de-los-campesinos-en-el-chile-actual\/\" target=\"_blank\"> <div class=\"icon__facebook-svg\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22.4px\" height=\"48.3px\" viewBox=\"0 0 22.4 48.3\" style=\"overflow:visible;enable-background:new 0 0 22.4 48.3;\" xml:space=\"preserve\">\n                <defs>\n                <\/defs>\n                <path class=\"st0\" d=\"M22.4,15.6h-7.6v-5c0-1.9,1.2-2.3,2.1-2.3c0.9,0,5.4,0,5.4,0V0l-7.4,0C6.6,0,4.8,6.2,4.8,10.1v5.5H0v8.5h4.8\n                    c0,10.9,0,24.1,0,24.1h10c0,0,0-13.3,0-24.1h6.8L22.4,15.6z\"><\/path>\n                <\/svg><\/a><\/div>\n                    <\/div><div class=\"icon__twitter-share-button\">\n                        <div class=\"icon__twitter-svg\"><a target=\"_blank\" href=\"http:\/\/twitter.com\/share?url=https:\/\/www.uoh.cl\/investigacion\/realidad-y-necesidades-de-los-campesinos-en-el-chile-actual\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/a><\/div>\n                        <\/div><div class=\"icon__linkedin-share-button\">\n                        <div class=\"icon__linkedin-svg\">\n                        <a target=\"__blank\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.uoh.cl\/investigacion\/realidad-y-necesidades-de-los-campesinos-en-el-chile-actual\/\"><svg enable-background=\"new 0 0 100 100\" height=\"100px\" id=\"Layer_1\" version=\"1.1\" viewBox=\"0 0 100 100\" width=\"100px\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><circle cx=\"50\" cy=\"50\" fill=\"#ccc\" r=\"45\"\/><g id=\"LinkedIn_1_\"><rect fill=\"#FFFFFF\" height=\"24.361\" width=\"7.69\" x=\"31.271\" y=\"43.569\"\/><path d=\"M59.968,43.334c-4.406,0-7.165,2.387-7.677,4.058v-3.823h-8.636c0.109,2.03,0,24.361,0,24.361h8.636    V54.748c0-0.733-0.034-1.465,0.19-1.991c0.594-1.464,1.869-2.985,4.162-2.985c2.998,0,4.361,2.253,4.361,5.552V67.93h8.721V54.384    C69.726,46.839,65.432,43.334,59.968,43.334z\" fill=\"#FFFFFF\"\/><path d=\"M34.973,32.069c-2.839,0-4.696,1.823-4.696,4.229c0,2.361,1.804,4.224,4.589,4.224h0.054    c2.891,0,4.69-1.869,4.69-4.229C39.555,33.888,37.81,32.069,34.973,32.069z\" fill=\"#FFFFFF\"\/><\/g><\/g><\/svg><\/a><\/div>\n\n            <\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_single_image image=&#8221;35948&#8243; img_size=&#8221;full&#8221; add_caption=&#8221;yes&#8221; alignment=&#8221;center&#8221; onclick=&#8221;img_link_large&#8221; img_link_target=&#8221;_blank&#8221; css=&#8221;&#8221;][vc_column_text]\u00a0[\/vc_column_text][vc_column_text css=&#8221;&#8221;]<\/p>\n<ul>\n<li style=\"font-weight: 400\">\u00a0<em>Mar\u00eda Cristina Hern\u00e1ndez, analista cualitativa del Observatorio Laboral de la Universidad de O\u2019Higgins explica los desaf\u00edos actuales de este sector a m\u00e1s de 45 a\u00f1os de la dictaci\u00f3n de las leyes sobre Reforma Agraria y Sindicalizaci\u00f3n Campesina.<\/em><\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_column_text]\u00a0[\/vc_column_text][vc_column_text css=&#8221;&#8221;]Durante el gobierno de Eduardo Frei Montalva se dictaron las leyes\u00a0<a href=\"https:\/\/www.bcn.cl\/leychile\/navegar?idNorma=28596\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.bcn.cl\/leychile\/navegar?idNorma%3D28596&amp;source=gmail&amp;ust=1722096051734000&amp;usg=AOvVaw0wyWLpw8h-X6msUHRRaxx9\">N\u00b0 16.640 de Reforma Agraria<\/a>\u00a0y la\u00a0<a href=\"https:\/\/www.bcn.cl\/leychile\/navegar?i=28586\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.bcn.cl\/leychile\/navegar?i%3D28586&amp;source=gmail&amp;ust=1722096051734000&amp;usg=AOvVaw1I0nt1BCRvUH5Gxvzwmg-L\">N\u00b0 16.625 sobre Sindicalizaci\u00f3n Campesina<\/a>, las que junto a otras normativas, implic\u00f3 un cambio radical en las formas de tenencia de la tierra, promovi\u00f3 la organizaci\u00f3n sindical y cambi\u00f3 las relaciones laborales, mejorando la calidad de vida de este importante sector productivo del pa\u00eds.<\/p>\n<p>Desde la dictaci\u00f3n de las leyes, que dieron origen al establecimiento del 28 de julio como el D\u00eda del Campesino, la situaci\u00f3n de ellas y ellos ha variado. Por ejemplo, antes de la Reforma Agraria, un 7% de las explotaciones (10 mil latifundios) concentraban el 81% de la superficie total y un 78% de la superficie agr\u00edcola. El nivel de sindicalizaci\u00f3n de los campesinos era muy bajo: 32 sindicatos con 2.118 afiliados en 1965. Con la Reforma Agraria -impulsada por los presidentes Eduardo Frei y Salvador Allende- se expropiaron 9,8 millones de hect\u00e1reas y 5.809 predios. La Ley de Sindicalizaci\u00f3n Campesina cre\u00f3 488 sindicatos con 127.688 afiliados en 1970, seg\u00fan los datos del\u00a0<a href=\"https:\/\/www.indap.gob.cl\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.indap.gob.cl\/&amp;source=gmail&amp;ust=1722096051734000&amp;usg=AOvVaw1NoNJxvq_wSmnSYJZbEsNm\">Instituto Nacional de Desarrollo Agropecuario (Indap)<\/a>.<\/p>\n<p>Y a 45 a\u00f1os de la dictaci\u00f3n de estas leyes, \u00bfHa cambiado el concepto que define si una persona es campesino\/a?\u00a0<a href=\"https:\/\/www.uoh.cl\/investigacion\/equipo\/maria-cristina-hernandez\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.uoh.cl\/investigacion\/equipo\/maria-cristina-hernandez\/&amp;source=gmail&amp;ust=1722096051734000&amp;usg=AOvVaw2hjvJDBnV-1dgrFqf3zbcq\">Mar\u00eda Cristina Hern\u00e1ndez<\/a>, analista cualitativa del\u00a0<a href=\"https:\/\/www.uoh.cl\/investigacion\/olo\/#:~:text=Su%20misi%C3%B3n%20es%20producir%20informaci%C3%B3n,de%20capacitaci%C3%B3n%2C%20productividad%20y%20empleabilidad.\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.uoh.cl\/investigacion\/olo\/%23:~:text%3DSu%2520misi%25C3%25B3n%2520es%2520producir%2520informaci%25C3%25B3n,de%2520capacitaci%25C3%25B3n%252C%2520productividad%2520y%2520empleabilidad.&amp;source=gmail&amp;ust=1722096051734000&amp;usg=AOvVaw19kFUBPlVJPIVufEg7afQN\">Observatorio Laboral de la Universidad de O\u2019Higgins<\/a>, se\u00f1ala que \u201ccuando hablamos de campesinos, estamos hablando de ruralidad y de agricultura, teniendo presente que lo rural y lo agr\u00edcola excede al mundo campesino, y a su vez, la vida campesina reviste una complejidad que va m\u00e1s all\u00e1 de la producci\u00f3n agropecuaria y el hecho de habitar en zonas rurales. Los campesinos y campesinas, viven en zonas rurales y trabajan unidades productivas de peque\u00f1o tama\u00f1o, organizando las labores, principalmente, con el trabajo propio y el de sus familias, del mismo modo que se apoyan entre trabajadores para tareas espec\u00edficas m\u00e1s intensivas en mano de obra\u201d.<\/p>\n<p>Por lo anterior, espec\u00edfica, la experta en el mundo campesino, \u00a0el campesino\/a como categor\u00eda, no incluye a todos los productores agr\u00edcolas ni a todos quienes trabajan en el agro, sino a quienes lo hacen a una escala espec\u00edfica e integrados en los territorios y en sus tradiciones.<\/p>\n<h4><b>La realidad en O&#8217;Higgins<\/b><\/h4>\n<p><b><\/b>Pese a no existir una cuantificaci\u00f3n exacta del campesinado en la Regi\u00f3n de O&#8217;Higgins, explica Mar\u00eda Cristina Hern\u00e1ndez, de acuerdo con el\u00a0<a href=\"http:\/\/www.censo2017.cl\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.censo2017.cl\/&amp;source=gmail&amp;ust=1722096051734000&amp;usg=AOvVaw0uU4TL6Eo6LfG-NZRSM9ym\">Censo 2017<\/a>, los habitantes rurales de la regi\u00f3n son un cuarto de la poblaci\u00f3n total. Asimismo, el \u00faltimo\u00a0<a href=\"https:\/\/www.ine.gob.cl\/docs\/default-source\/prensa-y-comunicacion\/nota-tecnica-caf-an%C3%A1lisis-de-los-estados-operativos-de-logro-y-no-logro.pdf?sfvrsn=4f059a36_2#:~:text=El%20VIII%20Censo%20Nacional%20Agropecuario,de%20un%2091%2C34%25.\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.ine.gob.cl\/docs\/default-source\/prensa-y-comunicacion\/nota-tecnica-caf-an%25C3%25A1lisis-de-los-estados-operativos-de-logro-y-no-logro.pdf?sfvrsn%3D4f059a36_2%23:~:text%3DEl%2520VIII%2520Censo%2520Nacional%2520Agropecuario,de%2520un%252091%252C34%2525.&amp;source=gmail&amp;ust=1722096051734000&amp;usg=AOvVaw3WunhzFOD7z8F38qKIvXEm\">Censo agropecuario<\/a>, indica que de las 9.130 Unidades Productivas Agropecuarias (UPA), el 67% no supera las 20 hect\u00e1reas y alrededor de un tercio las UPA (3.073), corresponden a Unidades Productivas de Autoconsumo. Adem\u00e1s, seg\u00fan informaci\u00f3n del\u00a0<a href=\"https:\/\/www.ine.gob.cl\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.ine.gob.cl\/&amp;source=gmail&amp;ust=1722096051734000&amp;usg=AOvVaw17_68EAFmGn_Rb29xtJTr3\">Instituto Nacional de Estad\u00edsticas (INE)<\/a>, quienes se emplean en el agro, representan alrededor del 15% de la poblaci\u00f3n regional, porcentaje dentro del cual se encuentra la poblaci\u00f3n campesina.<\/p>\n<p>En la zona \u2013al igual que en el resto del pa\u00eds- la organizaci\u00f3n de la agricultura campesina, desde su componente familiar y local, as\u00ed como su diversificaci\u00f3n productiva (ganader\u00eda, silvicultura, elaboraci\u00f3n de alimentos caseros, entre otros), ha sufrido importantes transformaciones. \u201cAl comparar al campesinado chileno de la Reforma Agraria con los actuales campesinos, se observan diferencias, donde es posible identificar algunos aspectos que amenazan su conservaci\u00f3n, como por ejemplo, el \u00e9xodo de j\u00f3venes rurales a las ciudades, el avance de los monocultivos y las parcelas de agrado, la crisis h\u00eddrica, el endeudamiento asociado al aumento de los precios de los insumos y la baja rentabilidad y una menor asociatividad al interior de la agricultura campesina, entre los principales temas\u201d, se\u00f1ala Mar\u00eda Cristina Hern\u00e1ndez.<\/p>\n<h4><b>Los desaf\u00edos actuales<\/b><\/h4>\n<p>Sobre los desaf\u00edos que enfrentan los campesinos\/as y la necesidad de pol\u00edticas p\u00fablicas que apoyen a este sector productivo, la analista cualitativa del Observatorio Laboral de la UOH, menciona que se requiere \u201cproteger las formas de vida campesina y con ellos a los peque\u00f1os\/as propietarios\/as de predios agr\u00edcolas y a los trabajadores\/as; generar formas de producci\u00f3n m\u00e1s eficientes y limpias en el uso de recursos naturales; incorporar innovaciones que faciliten las labores; agregar valor a los productos y disminuir los costos de producci\u00f3n, generando una mayor rentabilidad y dando acceso a mercados diversificados\u201d.<\/p>\n<p>A ello suma promover la asociatividad para la producci\u00f3n y comercializaci\u00f3n, optimizando y encadenando procesos y \u00a0generando \u201ccondiciones atractivas para retener a las generaciones j\u00f3venes, que son quienes pueden preservar y dar valor a la agricultura campesina, convirti\u00e9ndose en actores claves para la seguridad alimentaria y generaci\u00f3n de empleo local. Todo ello, sin dejar de visibilizar el papel de los mayores en el traspaso de conocimientos y tradiciones y resaltar el aporte de la mujer campesina a la econom\u00eda familiar -quien, adem\u00e1s de llevar toda la carga de las tareas dom\u00e9sticas al interior y exterior de la vivienda- genera ingresos mediante diversos emprendimientos\u201d, puntualiza Mar\u00eda Cristina Hern\u00e1ndez.[\/vc_column_text][vc_zigzag color=&#8221;white&#8221;][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650255686594{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center p-md-0 pt-5 pb-5&#8243;][vc_column el_class=&#8221;pb-5&#8243;][vc_row_inner el_class=&#8221;pb-5&#8243;][vc_column_inner]<div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0\"><h2 class=\"title title--decorator title--ms d-inline-block\">Te Recomendamos<\/h2><\/div><\/div><div class=\"content-holder\"><div class=\"row  swipper-news-list not--activate-hack \"><div class=\"row -wrapper\"><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/investigacion\/category\/observatorio-laboral\/\">\n                                        Observatorio Laboral<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2026\/05\/Observatorio-Laboral-1-scaled.jpg\" alt=\"Desocupaci\u00f3n se mantiene estable y brecha de g\u00e9nero se cierra por primera vez\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/1707;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Lunes 11, Mayo<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/investigacion\/desocupacion-se-mantiene-estable-y-brecha-de-genero-se-cierra-por-primera-vez\/\">\n                                    <h3 class=\"small-space\">Desocupaci\u00f3n se mantiene estable y brecha de g\u00e9nero se cierra por primera vez<\/h3><\/a>\n\n                                    <p>Mientras que la desocupaci\u00f3n en los hombres subi\u00f3 2,6 puntos, la de las mujeres baj\u00f3 3,6 puntos.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/investigacion\/desocupacion-se-mantiene-estable-y-brecha-de-genero-se-cierra-por-primera-vez\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/investigacion\/category\/investigacion\/\">\n                                        Investigaci\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2026\/04\/FWIS2026-web-op.jpg\" alt=\"Comienza proceso de postulaciones al Premio For Women in Science 2026\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/444;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Jueves 30, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/investigacion\/comienza-proceso-de-postulaciones-al-premio-for-women-in-science-2026\/\">\n                                    <h3 class=\"small-space\">Comienza proceso de postulaciones al Premio For Women in Science 2026<\/h3><\/a>\n\n                                    <p>La convocatoria, abierta entre el 22 de abril y el 28 de mayo de 2026, busca impulsar la trayectoria y aporte cient\u00edfico de investigadoras chilenas.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/investigacion\/comienza-proceso-de-postulaciones-al-premio-for-women-in-science-2026\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/investigacion\/category\/investigacion\/\">\n                                        Investigaci\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2026\/04\/Dia-de-la-Propiedad-Intelectual.jpg\" alt=\"UOH conmemora D\u00eda Mundial de la Propiedad Intelectual destacando avances en protecci\u00f3n\" style=\"--smush-placeholder-width: 2419px; --smush-placeholder-aspect-ratio: 2419\/1609;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Jueves 30, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/investigacion\/uoh-conmemora-dia-mundial-de-la-propiedad-intelectual-destacando-avances-en-proteccion\/\">\n                                    <h3 class=\"small-space\">UOH conmemora D\u00eda Mundial de la Propiedad Intelectual destacando avances en protecci\u00f3n<\/h3><\/a>\n\n                                    <p>La Direcci\u00f3n de Transferencia e Innovaci\u00f3n ha apoyado la protecci\u00f3n de 21 resultados de investigaci\u00f3n, concretado 11 solicitudes de patente, 12 registros de derechos de autor y 1 marca comercial.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/investigacion\/uoh-conmemora-dia-mundial-de-la-propiedad-intelectual-destacando-avances-en-proteccion\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pagination justify-content-center my-5\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/posts\/10678\/\/page\/2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/posts\/10678\/\/page\/3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/posts\/10678\/\/page\/132\">132<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/posts\/10678\/\/page\/2\"><div class=\"icon-pagination-next\"> <?xml version=\"1.0\" ?><svg viewBox=\"0 0 96 96\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><title\/><path d=\"M39.3756,48.0022l30.47-25.39a6.0035,6.0035,0,0,0-7.6878-9.223L26.1563,43.3906a6.0092,6.0092,0,0,0,0,9.2231L62.1578,82.615a6.0035,6.0035,0,0,0,7.6878-9.2231Z\"\/><\/svg> <\/div><\/a><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Mar\u00eda Cristina Hern\u00e1ndez, analista cualitativa del Observatorio Laboral de la Universidad de O\u2019Higgins explica los desaf\u00edos actuales de este sector a m\u00e1s de 45 a\u00f1os de la dictaci\u00f3n de las leyes sobre Reforma Agraria y Sindicalizaci\u00f3n Campesina.<\/p>\n","protected":false},"author":34,"featured_media":10681,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[190],"tags":[],"class_list":["post-10678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-observatorio-laboral"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Realidad y necesidades campesinas en el Chile actual - Investigaci\u00f3n<\/title>\n<meta name=\"description\" content=\"Las carreras de Pedagog\u00eda en Educaci\u00f3n B\u00e1sica, Pedagog\u00eda en Matem\u00e1tica, Pedagog\u00eda en Lenguaje y Comunicaci\u00f3n y Pedagog\u00eda en Ciencias Naturales realizaron diversas actividades en el marco de lo dictado por el Ministerio de Educaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Realidad y necesidades campesinas en el Chile actual - Investigaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Las carreras de Pedagog\u00eda en Educaci\u00f3n B\u00e1sica, Pedagog\u00eda en Matem\u00e1tica, Pedagog\u00eda en Lenguaje y Comunicaci\u00f3n y Pedagog\u00eda en Ciencias Naturales realizaron diversas actividades en el marco de lo dictado por el Ministerio de Educaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/investigacion\/realidad-y-necesidades-de-los-campesinos-en-el-chile-actual\/\" \/>\n<meta property=\"og:site_name\" content=\"Investigaci\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-26T16:00:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-26T18:57:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2024\/07\/Campesinos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Universidad de O&#039;Higgins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Universidad de O&#039;Higgins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/realidad-y-necesidades-de-los-campesinos-en-el-chile-actual\/\",\"url\":\"https:\/\/www.uoh.cl\/investigacion\/realidad-y-necesidades-de-los-campesinos-en-el-chile-actual\/\",\"name\":\"Realidad y necesidades campesinas en el Chile actual - Investigaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/realidad-y-necesidades-de-los-campesinos-en-el-chile-actual\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/realidad-y-necesidades-de-los-campesinos-en-el-chile-actual\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2024\/07\/Campesinos.jpg\",\"datePublished\":\"2024-07-26T16:00:14+00:00\",\"dateModified\":\"2024-07-26T18:57:02+00:00\",\"author\":{\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"description\":\"Las carreras de Pedagog\u00eda en Educaci\u00f3n B\u00e1sica, Pedagog\u00eda en Matem\u00e1tica, Pedagog\u00eda en Lenguaje y Comunicaci\u00f3n y Pedagog\u00eda en Ciencias Naturales realizaron diversas actividades en el marco de lo dictado por el Ministerio de Educaci\u00f3n.\",\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uoh.cl\/investigacion\/realidad-y-necesidades-de-los-campesinos-en-el-chile-actual\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/realidad-y-necesidades-de-los-campesinos-en-el-chile-actual\/#primaryimage\",\"url\":\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2024\/07\/Campesinos.jpg\",\"contentUrl\":\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2024\/07\/Campesinos.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/#website\",\"url\":\"https:\/\/www.uoh.cl\/investigacion\/\",\"name\":\"Investigaci\u00f3n\",\"description\":\"Sitio web de investigaci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uoh.cl\/investigacion\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\",\"name\":\"Universidad de O'Higgins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"caption\":\"Universidad de O'Higgins\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Realidad y necesidades campesinas en el Chile actual - Investigaci\u00f3n","description":"Las carreras de Pedagog\u00eda en Educaci\u00f3n B\u00e1sica, Pedagog\u00eda en Matem\u00e1tica, Pedagog\u00eda en Lenguaje y Comunicaci\u00f3n y Pedagog\u00eda en Ciencias Naturales realizaron diversas actividades en el marco de lo dictado por el Ministerio de Educaci\u00f3n.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Realidad y necesidades campesinas en el Chile actual - Investigaci\u00f3n","og_description":"Las carreras de Pedagog\u00eda en Educaci\u00f3n B\u00e1sica, Pedagog\u00eda en Matem\u00e1tica, Pedagog\u00eda en Lenguaje y Comunicaci\u00f3n y Pedagog\u00eda en Ciencias Naturales realizaron diversas actividades en el marco de lo dictado por el Ministerio de Educaci\u00f3n.","og_url":"https:\/\/www.uoh.cl\/investigacion\/realidad-y-necesidades-de-los-campesinos-en-el-chile-actual\/","og_site_name":"Investigaci\u00f3n","article_published_time":"2024-07-26T16:00:14+00:00","article_modified_time":"2024-07-26T18:57:02+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2024\/07\/Campesinos.jpg","type":"image\/jpeg"}],"author":"Universidad de O'Higgins","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Universidad de O'Higgins","Tiempo estimado de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/investigacion\/realidad-y-necesidades-de-los-campesinos-en-el-chile-actual\/","url":"https:\/\/www.uoh.cl\/investigacion\/realidad-y-necesidades-de-los-campesinos-en-el-chile-actual\/","name":"Realidad y necesidades campesinas en el Chile actual - Investigaci\u00f3n","isPartOf":{"@id":"https:\/\/www.uoh.cl\/investigacion\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uoh.cl\/investigacion\/realidad-y-necesidades-de-los-campesinos-en-el-chile-actual\/#primaryimage"},"image":{"@id":"https:\/\/www.uoh.cl\/investigacion\/realidad-y-necesidades-de-los-campesinos-en-el-chile-actual\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2024\/07\/Campesinos.jpg","datePublished":"2024-07-26T16:00:14+00:00","dateModified":"2024-07-26T18:57:02+00:00","author":{"@id":"https:\/\/www.uoh.cl\/investigacion\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"description":"Las carreras de Pedagog\u00eda en Educaci\u00f3n B\u00e1sica, Pedagog\u00eda en Matem\u00e1tica, Pedagog\u00eda en Lenguaje y Comunicaci\u00f3n y Pedagog\u00eda en Ciencias Naturales realizaron diversas actividades en el marco de lo dictado por el Ministerio de Educaci\u00f3n.","inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/investigacion\/realidad-y-necesidades-de-los-campesinos-en-el-chile-actual\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/investigacion\/realidad-y-necesidades-de-los-campesinos-en-el-chile-actual\/#primaryimage","url":"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2024\/07\/Campesinos.jpg","contentUrl":"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2024\/07\/Campesinos.jpg","width":1000,"height":1000},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/investigacion\/#website","url":"https:\/\/www.uoh.cl\/investigacion\/","name":"Investigaci\u00f3n","description":"Sitio web de investigaci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/investigacion\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/www.uoh.cl\/investigacion\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f","name":"Universidad de O'Higgins","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/investigacion\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","caption":"Universidad de O'Higgins"}}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/posts\/10678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/comments?post=10678"}],"version-history":[{"count":1,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/posts\/10678\/revisions"}],"predecessor-version":[{"id":10680,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/posts\/10678\/revisions\/10680"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/media\/10681"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/media?parent=10678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/categories?post=10678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/tags?post=10678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}