
{"id":7928,"date":"2023-03-23T15:10:13","date_gmt":"2023-03-23T18:10:13","guid":{"rendered":"https:\/\/www.uoh.cl\/investigacion\/?post_type=academics&#038;p=7928"},"modified":"2026-05-13T07:17:26","modified_gmt":"2026-05-13T10:17:26","slug":"ngaire-honey","status":"publish","type":"academics","link":"https:\/\/www.uoh.cl\/investigacion\/academico\/ngaire-honey\/","title":{"rendered":"Ngaire Honey"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1650056176159{padding-top: 3rem !important;}&#8221;][vc_row][vc_column][vc_wp_custommenu nav_menu=&#8221;5&#8243;]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/investigacion\"><span itemprop=\"name\">Investigaci\u00f3n<\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/investigacion\"><span itemprop=\"name\">Investigaci\u00f3n<\/span><\/a><meta itemprop=\"position\" content=\"3\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/investigacion\/academicos\"><span itemprop=\"name\">Acad\u00e9micos<\/span><\/a><meta itemprop=\"position\" content=\"4\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Ngaire Honey <\/span><meta itemprop=\"position\" content=\"5\" \/><\/ol><\/div><ul class=\"p-0 list-style-none d-inline-block\"><li class=\"p-0\"><a href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\" class=\"px-1 py-2\">\n                            Instituto de Ciencias de la Educaci\u00f3n\n                        <\/a><\/li><\/ul><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block big\">Ngaire Honey<em class=\"position__title\"> <span>\u25cf<\/span> Profesora Asistente<\/em><\/h1><\/div>[vc_row_inner el_class=&#8221;border-separator m-0 mt-4&#8243;][vc_column_inner width=&#8221;1\/6&#8243;]<div class=\"vc_single_image-wrapper vc_box_rounded  vc_box_border_grey\"><img decoding=\"async\" width=\"1000\" height=\"1000\" data-src=\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2023\/03\/Ngaire-Honey-1.png\" class=\"attachment-large size-large wp-post-image lazyload\" alt=\"Ngaire Honey\" data-srcset=\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2023\/03\/Ngaire-Honey-1.png 1000w, https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2023\/03\/Ngaire-Honey-1-300x300.png 300w, https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2023\/03\/Ngaire-Honey-1-150x150.png 150w, https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2023\/03\/Ngaire-Honey-1-768x768.png 768w, https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2023\/03\/Ngaire-Honey-1-600x600.png 600w\" data-sizes=\"(max-width: 1000px) 100vw, 1000px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1000px; --smush-placeholder-aspect-ratio: 1000\/1000;\" \/><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;2\/3&#8243;]<div class=\"block--info\">\n                                <div class=\"sub_title__grade\">Grado Acad\u00e9mico<\/div>\n                                <h3>Doctora en Liderazgo y Estudio de Pol\u00edticas, Universidad de Vanderbilt, Nashville EEUU.<\/h3> <\/div><div class=\"block--info\">\n                                <div class=\"sub_title__grade\">T\u00edtulo(s) Profesional<\/div>\n                                <h3>Mag\u00edster en Estudios Latinoamericanos, Tulane University. Licenciatura en Relaciones Exteriores y Espa\u00f1ol, Wartburg College.<\/h3> <\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;]<div class=\"uoh_social_network_component uoh_row col-12 justify-content-end m-0 p-0\"> <div class=\"icon__facebook-share-button\">\n                       <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.uoh.cl\/investigacion\/academico\/ngaire-honey\/\" target=\"_blank\"> <div class=\"icon__facebook-svg\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22.4px\" height=\"48.3px\" viewBox=\"0 0 22.4 48.3\" style=\"overflow:visible;enable-background:new 0 0 22.4 48.3;\" xml:space=\"preserve\">\n                <defs>\n                <\/defs>\n                <path class=\"st0\" d=\"M22.4,15.6h-7.6v-5c0-1.9,1.2-2.3,2.1-2.3c0.9,0,5.4,0,5.4,0V0l-7.4,0C6.6,0,4.8,6.2,4.8,10.1v5.5H0v8.5h4.8\n                    c0,10.9,0,24.1,0,24.1h10c0,0,0-13.3,0-24.1h6.8L22.4,15.6z\"><\/path>\n                <\/svg><\/a><\/div>\n                    <\/div><div class=\"icon__twitter-share-button\">\n                        <div class=\"icon__twitter-svg\"><a target=\"_blank\" href=\"http:\/\/twitter.com\/share?url=https:\/\/www.uoh.cl\/investigacion\/academico\/ngaire-honey\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/a><\/div>\n                        <\/div><div class=\"icon__linkedin-share-button\">\n                        <div class=\"icon__linkedin-svg\">\n                        <a target=\"__blank\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.uoh.cl\/investigacion\/academico\/ngaire-honey\/\"><svg enable-background=\"new 0 0 100 100\" height=\"100px\" id=\"Layer_1\" version=\"1.1\" viewBox=\"0 0 100 100\" width=\"100px\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><circle cx=\"50\" cy=\"50\" fill=\"#ccc\" r=\"45\"\/><g id=\"LinkedIn_1_\"><rect fill=\"#FFFFFF\" height=\"24.361\" width=\"7.69\" x=\"31.271\" y=\"43.569\"\/><path d=\"M59.968,43.334c-4.406,0-7.165,2.387-7.677,4.058v-3.823h-8.636c0.109,2.03,0,24.361,0,24.361h8.636    V54.748c0-0.733-0.034-1.465,0.19-1.991c0.594-1.464,1.869-2.985,4.162-2.985c2.998,0,4.361,2.253,4.361,5.552V67.93h8.721V54.384    C69.726,46.839,65.432,43.334,59.968,43.334z\" fill=\"#FFFFFF\"\/><path d=\"M34.973,32.069c-2.839,0-4.696,1.823-4.696,4.229c0,2.361,1.804,4.224,4.589,4.224h0.054    c2.891,0,4.69-1.869,4.69-4.229C39.555,33.888,37.81,32.069,34.973,32.069z\" fill=\"#FFFFFF\"\/><\/g><\/g><\/svg><\/a><\/div>\n\n            <\/div><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650239278498{background-color: #ffffff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center&#8221;][vc_column][vc_row_inner][vc_column_inner width=&#8221;5\/6&#8243;]<div class=\"uoh_title_component-container\"><h4 class=\"title title--ms d-inline-block title--decorator  small\">Descripci\u00f3n<\/h4><\/div><p class=\"info-headings mb-2 text-left mt-4 mt-md-2\">Ngaire Honey posee un doctorado en Leadership and Policy Studies de la Universidad de Vanderbilt, Nashville EEUU, realiz\u00f3 su tesis sobre segregaci\u00f3n escolar y c\u00f3mo la disponibilidad y potencial acceso al sistema de transporte p\u00fablico pueden impactar el aislamiento escolar y la distribuci\u00f3n de estudiantes. Obtuvo su Mag\u00edster en Estudios Latinoamericanos en la Universidad de Tulane, New Orleans EEUU, y su pregrado en Relaciones Internacionales en Wartburg College, Waverly EEUU . Llega a Chile para investigar el efecto del nuevo sistema de admisi\u00f3n escolar en el acceso educativo y la segregaci\u00f3n estudiantil. Desde entonces, ha centrado sus investigaciones en pol\u00edticas educativas con enfoque en el acceso a la educaci\u00f3n, las trayectorias educativas, la opini\u00f3n p\u00fablica, la educaci\u00f3n en contextos de ruralidad, justicia educacional y los mercados y reformas educativas.<\/p>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650056119592{background-color: #ffffff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5 pb-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-start&#8221;][vc_column width=&#8221;1\/6&#8243; el_class=&#8221;p-0&#8243;]<div class=\"uoh_link_component pe-4 d-inline-block py-1 button_icon inline\"><i class=\"me-2 fas fa-newspaper\" style=\"color: #42a0f8\"><\/i><span>Publicaciones<\/span><\/div><div class=\"wpb_text_column wpb_content_element  citas mb-3 pb-3\"><div class=\"wpb_wrapper\"><p>7<\/p><\/div><\/div><div class=\"uoh_link_component pe-4 d-inline-block py-1 button_icon inline\"><i class=\"me-2 fas fa-project-diagram\" style=\"color: #42a0f8\"><\/i><span>Proyectos<\/span><\/div><div class=\"wpb_text_column wpb_content_element  citas mb-3 pb-3\"><div class=\"wpb_wrapper\"><p>5<\/p><\/div><\/div><div class=\"uoh_link_component pe-4 d-inline-block py-1 button_icon inline\"><i class=\"me-2 fas fa-book-bookmark\" style=\"color: #42a0f8\"><\/i><span>Cap\u00edtulos de Libros<\/span><\/div><div class=\"wpb_text_column wpb_content_element  citas mb-3 pb-3\"><div class=\"wpb_wrapper\"><p>2<\/p><\/div><\/div><div class=\"uoh_link_component pe-4 d-inline-block py-1 button_icon inline\"><i class=\"me-2 fas fa-feather-pointed\" style=\"color: #42a0f8\"><\/i><span>Otros Escritos<\/span><\/div><div class=\"wpb_text_column wpb_content_element  citas mb-3 pb-3\"><div class=\"wpb_wrapper\"><p>2<\/p><\/div><\/div>[\/vc_column][vc_column width=&#8221;5\/6&#8243;][vc_tta_tabs active_section=&#8221;1&#8243; el_class=&#8221;tabs-inner-academic&#8221;][vc_tta_section title=&#8221;Publicaciones&#8221; tab_id=&#8221;publicaciones&#8221;]<link rel=\"stylesheet\" id=\"font-awesome-css\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.5.1\/css\/all.min.css\" type=\"text\/css\" media=\"all\"><div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0 px-md-0 \"><\/div><\/div>[\/vc_tta_section][vc_tta_section title=&#8221;Proyectos&#8221; tab_id=&#8221;proyectos&#8221;]<link rel=\"stylesheet\" id=\"font-awesome-css\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.5.1\/css\/all.min.css\" type=\"text\/css\" media=\"all\"><div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0 px-md-0 \"><\/div><\/div>[\/vc_tta_section][vc_tta_section title=&#8221;Cap\u00edtulos de Libros&#8221; tab_id=&#8221;cap-libros&#8221;]<link rel=\"stylesheet\" id=\"font-awesome-css\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.5.1\/css\/all.min.css\" type=\"text\/css\" media=\"all\"><div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0 px-md-0 \"><\/div><\/div><div class=\"content-holder row m-0 p-0 aling-items-center pt-5 pb-5 \"><div class=\"row  large--swipper-content p-0 \"><div class=\"\"><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> De la Reforma a la Transformaci\u00f3n: Capacidades, Innovaciones y Regulaci\u00f3n de la Educaci\u00f3n Chilena<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">El nuevo sistema de admisi\u00f3n escolar: \u00bfConviene Reformarlo?<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Ediciones UC<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Carrasco, & Flores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Alejandro Carrasco, Ngaire Noelle Honey, Juan de Dios Oyarz\u00fan, Ang\u00e9lica Bonilla<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> De la Reforma a la Transformaci\u00f3n: Capacidades, Innovaciones y Regulaci\u00f3n de la Educaci\u00f3n Chilena<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">El nuevo sistema de admisi\u00f3n escolar: \u00bfConviene Reformarlo?<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Ediciones UC<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Carrasco, & Flores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Alejandro Carrasco, Ngaire Noelle Honey, Juan de Dios Oyarz\u00fan, Ang\u00e9lica Bonilla<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Twenty Years Later:  Migrant Youth in North America.<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">NAFTA and immigration: A sociodemographic profile of Mexican Individuals in the U.S. and Mexico across three decades.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">PIERAN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Stella Flores, Ngaire Noelle Honey<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Twenty Years Later:  Migrant Youth in North America.<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">NAFTA and immigration: A sociodemographic profile of Mexican Individuals in the U.S. and Mexico across three decades.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">PIERAN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Stella Flores, Ngaire Noelle Honey<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>[\/vc_tta_section][vc_tta_section title=&#8221;Otros escritos e informes&#8221; tab_id=&#8221;otros&#8221;]<link rel=\"stylesheet\" id=\"font-awesome-css\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.5.1\/css\/all.min.css\" type=\"text\/css\" media=\"all\"><div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0 px-md-0 \"><\/div><\/div><div class=\"content-holder row m-0 p-0 aling-items-center pt-5 pb-5 \"><div class=\"row  large--swipper-content p-0 \"><div class=\"\"><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Manual de buenas pr\u00e1cticas en tratamientos por inmersi\u00f3n contra Caligus rogercresseyi<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Sandra L. Mar\u00edn, Gabriel Alejandro Arriagada Acevedo<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Manual de buenas pr\u00e1cticas en tratamientos por inmersi\u00f3n contra Caligus rogercresseyi<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Sandra L. Mar\u00edn, Gabriel Alejandro Arriagada Acevedo<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Interna<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Manual para escritura y presentaci\u00f3n de tesinas (ECA3)<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Manual de Tesis de pregrado ECA3<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Camila Soto, Catalina Javiera Pinto Palacios, Nicolas Osvaldo Quiroga Barrera, Paula Andrea Irles Ivanac, Paula Macarena Toro Mujica, Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Interna<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Manual para escritura y presentaci\u00f3n de tesinas (ECA3)<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Manual de Tesis de pregrado ECA3<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Camila Soto, Catalina Javiera Pinto Palacios, Nicolas Osvaldo Quiroga Barrera, Paula Andrea Irles Ivanac, Paula Macarena Toro Mujica, Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/www.drosu.cl\/assets\/apps\/documentos\/f2988798-33ac-410b-8bea-24cad07dfc8c.pdf<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Manual de campo Identificaci\u00f3n y monitoreo<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Proyecto financiado a trav\u00e9s del Fondo\r\nde Innovaci\u00f3n para la Competitividad\r\ndel Gobierno Regional de O\u00b4Higgins y\r\nsu Consejo Regional, enmarcado en la\r\nEstrategia Regional de Innovaci\u00f3n<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Paula Andrea Irles Ivanac, Equipo FIC Drosophila<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/www.drosu.cl\/assets\/apps\/documentos\/f2988798-33ac-410b-8bea-24cad07dfc8c.pdf<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Manual de campo Identificaci\u00f3n y monitoreo<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Proyecto financiado a trav\u00e9s del Fondo\r\nde Innovaci\u00f3n para la Competitividad\r\ndel Gobierno Regional de O\u00b4Higgins y\r\nsu Consejo Regional, enmarcado en la\r\nEstrategia Regional de Innovaci\u00f3n<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Paula Andrea Irles Ivanac, Equipo FIC Drosophila<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Interna<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Manual para escritura y presentaci\u00f3n de tesinas (ECA3)<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Manual de Tesis de pregrado ECA3<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Camila Soto, Catalina Javiera Pinto Palacios, Nicolas Osvaldo Quiroga Barrera, Paula Andrea Irles Ivanac, Paula Macarena Toro Mujica, Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Interna<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Manual para escritura y presentaci\u00f3n de tesinas (ECA3)<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Manual de Tesis de pregrado ECA3<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Camila Soto, Catalina Javiera Pinto Palacios, Nicolas Osvaldo Quiroga Barrera, Paula Andrea Irles Ivanac, Paula Macarena Toro Mujica, Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Digital y f\u00edsica<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Luz, c\u00e1mara&#8230; \u00a1A leer!: experiencias de mediaci\u00f3n lectora (PR\u00d3LOGO)<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Proyecto FID desarrollado por estudiantes de Pedagog\u00eda en Educaci\u00f3n B\u00e1sica.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Pr\u00f3logo de libro (Proyecto FID desarrollado por estudiantes de Ped. Ed. B\u00e1sica)<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Isabel Ibaceta<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Digital y f\u00edsica<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Luz, c\u00e1mara&#8230; \u00a1A leer!: experiencias de mediaci\u00f3n lectora (PR\u00d3LOGO)<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Proyecto FID desarrollado por estudiantes de Pedagog\u00eda en Educaci\u00f3n B\u00e1sica.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Pr\u00f3logo de libro (Proyecto FID desarrollado por estudiantes de Ped. Ed. B\u00e1sica)<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Isabel Ibaceta<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> f\u00edsica y digital<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Tu historia, nuestra historia (PR\u00d3LOGO)<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">kjdlkfjsdlkfjlksdf<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Pr\u00f3logo (Asociado a proyecto FID desarrollado por estudiantes de Ped. en Leng. y Com.)<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Camila P\u00e9rez Navarro, Isabel Ibaceta<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> f\u00edsica y digital<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Tu historia, nuestra historia (PR\u00d3LOGO)<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">kjdlkfjsdlkfjlksdf<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Pr\u00f3logo (Asociado a proyecto FID desarrollado por estudiantes de Ped. en Leng. y Com.)<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Camila P\u00e9rez Navarro, Isabel Ibaceta<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Regional y Nacional<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Descentralizando y visibilizando la producci\u00f3n editorial regional<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">El pr\u00f3logo abre el libro titulado \"Paisaje Editorial: Librodiversidades y Bibliodiversidades de\r\nla Regi\u00f3n de O'Higgins (2023).\r\n\r\nEste libro es el producto final de un proyecto de investigaci\u00f3n adjudicado por la acad\u00e9mica en la SEREMI de las Culturas, las\r\nArtes y el Patrimonio de la Regi\u00f3n del Libertador General Bernardo O &#769;Higgins y patrocinado por la Direcci\u00f3n de Cultura, Patrimonio y Extensi\u00f3n UOH.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Pr\u00f3logo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Isabel Ibaceta<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Regional y Nacional<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Descentralizando y visibilizando la producci\u00f3n editorial regional<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">El pr\u00f3logo abre el libro titulado \"Paisaje Editorial: Librodiversidades y Bibliodiversidades de\r\nla Regi\u00f3n de O'Higgins (2023).\r\n\r\nEste libro es el producto final de un proyecto de investigaci\u00f3n adjudicado por la acad\u00e9mica en la SEREMI de las Culturas, las\r\nArtes y el Patrimonio de la Regi\u00f3n del Libertador General Bernardo O &#769;Higgins y patrocinado por la Direcci\u00f3n de Cultura, Patrimonio y Extensi\u00f3n UOH.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Pr\u00f3logo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Isabel Ibaceta<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> CNA e interna<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Informe de Autoevaluaci\u00f3n Proceso de Acreditaci\u00f3n PEB (5 a\u00f1os de acreditaci\u00f3n)<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">En el rol de jefatura, liderar el proceso de autoevaluaci\u00f3n de la carrera que deriva finalmente en la elaboraci\u00f3n del informe.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe de Autoevaluaci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Miguel Alejandro Ramos Riquelme, Comit\u00e9 de autoevaluaci\u00f3n PEB<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> CNA e interna<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Informe de Autoevaluaci\u00f3n Proceso de Acreditaci\u00f3n PEB (5 a\u00f1os de acreditaci\u00f3n)<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">En el rol de jefatura, liderar el proceso de autoevaluaci\u00f3n de la carrera que deriva finalmente en la elaboraci\u00f3n del informe.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe de Autoevaluaci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Miguel Alejandro Ramos Riquelme, Comit\u00e9 de autoevaluaci\u00f3n PEB<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Informe del Patrimonio Paleontol\u00f3gico y Arqueol\u00f3gico de la comuna de San Vicente de Tagua Tagua<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">La Ilustre Municipalidad de San Vicente de Tagua Tagua me encarg\u00f3 la confecci\u00f3n del informe. Posterior a este documento, el proyecto Tagua Tagua Milenaria comenz\u00f3 a desarrollarse hasta hoy en d\u00eda<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Erwin Gonz\u00e1lez<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Informe del Patrimonio Paleontol\u00f3gico y Arqueol\u00f3gico de la comuna de San Vicente de Tagua Tagua<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">La Ilustre Municipalidad de San Vicente de Tagua Tagua me encarg\u00f3 la confecci\u00f3n del informe. Posterior a este documento, el proyecto Tagua Tagua Milenaria comenz\u00f3 a desarrollarse hasta hoy en d\u00eda<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Erwin Gonz\u00e1lez<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Planificaci\u00f3n y revisi\u00f3n de la escritura en estudiantes chilenas de 3\u00b0, 6\u00b0 y 9\u00b0 grado<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Enlace: https:\/\/ciae.uchile.cl\/index.php?page=view_biblioteca_digital&id=1081&langSite=es<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Working paper<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Elvira J\u00e9ldrez, Carmen Sotomayor, David Maximiliano G\u00f3mez Rojas<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Planificaci\u00f3n y revisi\u00f3n de la escritura en estudiantes chilenas de 3\u00b0, 6\u00b0 y 9\u00b0 grado<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Enlace: https:\/\/ciae.uchile.cl\/index.php?page=view_biblioteca_digital&id=1081&langSite=es<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Working paper<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Elvira J\u00e9ldrez, Carmen Sotomayor, David Maximiliano G\u00f3mez Rojas<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Interna<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Manual para escritura y presentaci\u00f3n de tesinas (ECA3)<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Manual de Tesis de pregrado ECA3<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Camila Soto, Catalina Javiera Pinto Palacios, Nicolas Osvaldo Quiroga Barrera, Paula Andrea Irles Ivanac, Paula Macarena Toro Mujica, Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Interna<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Manual para escritura y presentaci\u00f3n de tesinas (ECA3)<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Manual de Tesis de pregrado ECA3<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Camila Soto, Catalina Javiera Pinto Palacios, Nicolas Osvaldo Quiroga Barrera, Paula Andrea Irles Ivanac, Paula Macarena Toro Mujica, Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Privada<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Reportes de Diagn\u00f3stico Fitosanitario<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">sfdsgfd<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informes de Laboratorio<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Privada<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Reportes de Diagn\u00f3stico Fitosanitario<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">sfdsgfd<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informes de Laboratorio<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> P\u00e1gina web<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">C\u00e1ncer bacteriano del cerezo (Pseudomonas syringae pv syringae): Etiolog\u00eda, ciclo biol\u00f3gico epidemiolog\u00eda, sintomatolog\u00eda, diagn\u00f3stico y manejo integrado<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">El foco de este bolet\u00edn es proporcionar algunos antecedentes resumidos de etiolog\u00eda, ciclo biol\u00f3gico y epidemiolog\u00eda de la enfermedad, proponer directrices tecnol\u00f3gicas b\u00e1sicas para el manejo integrado del c\u00e1ncer bacteriano del cerezo en la zona sur de Chile y sintomatologia predominante. Los antecedentes que se presentan en este documento han sido adaptados desde literatura consultada de publicaciones nacionales e internacionales referidas a las enfermedades del cultivo del cerezo, y principalmente de la experiencia pr\u00e1ctica de los\r\nautores y de resultados obtenidos del proyecto CORFO. Centro para la Investigaci\u00f3n e Innovaci\u00f3n en Fruticultura para La Zona Sur. (C\u00f3digo 16PTECFS-66647), 2017-2021; \u00c1rea 3. Paquete tecnol\u00f3gico para manejo sanitario de huertos. T\u00f3pico 1. Susceptibilidad, prevenci\u00f3n y control de c\u00e1ncer bacteriano.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Bolet\u00edn T\u00e9cnico<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jaime Guerrero Contreras, Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> P\u00e1gina web<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">C\u00e1ncer bacteriano del cerezo (Pseudomonas syringae pv syringae): Etiolog\u00eda, ciclo biol\u00f3gico epidemiolog\u00eda, sintomatolog\u00eda, diagn\u00f3stico y manejo integrado<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">El foco de este bolet\u00edn es proporcionar algunos antecedentes resumidos de etiolog\u00eda, ciclo biol\u00f3gico y epidemiolog\u00eda de la enfermedad, proponer directrices tecnol\u00f3gicas b\u00e1sicas para el manejo integrado del c\u00e1ncer bacteriano del cerezo en la zona sur de Chile y sintomatologia predominante. Los antecedentes que se presentan en este documento han sido adaptados desde literatura consultada de publicaciones nacionales e internacionales referidas a las enfermedades del cultivo del cerezo, y principalmente de la experiencia pr\u00e1ctica de los\r\nautores y de resultados obtenidos del proyecto CORFO. Centro para la Investigaci\u00f3n e Innovaci\u00f3n en Fruticultura para La Zona Sur. (C\u00f3digo 16PTECFS-66647), 2017-2021; \u00c1rea 3. Paquete tecnol\u00f3gico para manejo sanitario de huertos. T\u00f3pico 1. Susceptibilidad, prevenci\u00f3n y control de c\u00e1ncer bacteriano.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Bolet\u00edn T\u00e9cnico<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jaime Guerrero Contreras, Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> P\u00e1gina web<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Hongos de la madera del cerezo<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Los hongos de la madera, como Chondrostereum purpureum, Cytospora spp. y Calosphaeria spp, constituyen un grupo de fitopat\u00f3genos clave, que pueden comprometer seriamente la salud y productividad del cultivo del cerezo en Chile; esto, en el entendido que los hongos que atacan a la madera encuentran a menudo nichos ecol\u00f3gicos \u00f3ptimos para su desarrollo y proliferaci\u00f3n, lo que requiere una vigilancia constante y estrategias adaptativas por parte de los\r\nagricultores y profesionales del \u00e1rea. La identificaci\u00f3n temprana de s\u00edntomas, el correcto diagn\u00f3stico de las enfermedades y la implementaci\u00f3n de pr\u00e1cticas de manejo integrado de enfermedades se presentan como piedras angulares en la estrategia de mitigaci\u00f3n de este y otros problemas fitosanitarios.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Bolet\u00edn T\u00e9cnico<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jaime Guerrero Contreras, Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> P\u00e1gina web<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Hongos de la madera del cerezo<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Los hongos de la madera, como Chondrostereum purpureum, Cytospora spp. y Calosphaeria spp, constituyen un grupo de fitopat\u00f3genos clave, que pueden comprometer seriamente la salud y productividad del cultivo del cerezo en Chile; esto, en el entendido que los hongos que atacan a la madera encuentran a menudo nichos ecol\u00f3gicos \u00f3ptimos para su desarrollo y proliferaci\u00f3n, lo que requiere una vigilancia constante y estrategias adaptativas por parte de los\r\nagricultores y profesionales del \u00e1rea. La identificaci\u00f3n temprana de s\u00edntomas, el correcto diagn\u00f3stico de las enfermedades y la implementaci\u00f3n de pr\u00e1cticas de manejo integrado de enfermedades se presentan como piedras angulares en la estrategia de mitigaci\u00f3n de este y otros problemas fitosanitarios.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Bolet\u00edn T\u00e9cnico<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jaime Guerrero Contreras, Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> P\u00e1gina web<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Enfermedades del Avellano Europeo: Alternaria, necrosis marginal en hojas<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Serie de Fichas t\u00e9cnicas que aportan informaci\u00f3n al productor de avellana europea.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Ficha T\u00e9cnica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jaime Guerrero Contreras, Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> P\u00e1gina web<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Enfermedades del Avellano Europeo: Alternaria, necrosis marginal en hojas<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Serie de Fichas t\u00e9cnicas que aportan informaci\u00f3n al productor de avellana europea.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Ficha T\u00e9cnica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jaime Guerrero Contreras, Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> P\u00e1gina web<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Enfermedades del Avellano Europeo: Fisiopat\u00eda de la mancha parda en avellana<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Serie de Fichas t\u00e9cnicas que aportan informaci\u00f3n al productor de avellana europea.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Ficha T\u00e9cnica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jaime Guerrero Contreras, Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> P\u00e1gina web<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Enfermedades del Avellano Europeo: Fisiopat\u00eda de la mancha parda en avellana<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Serie de Fichas t\u00e9cnicas que aportan informaci\u00f3n al productor de avellana europea.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Ficha T\u00e9cnica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jaime Guerrero Contreras, Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> P\u00e1gina web<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Enfermedades del Avellano Europeo: Hongos de la madera<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Serie de Fichas t\u00e9cnicas que aportan informaci\u00f3n al productor de avellana europea.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Ficha T\u00e9cnica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jaime Guerrero Contreras, Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> P\u00e1gina web<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Enfermedades del Avellano Europeo: Hongos de la madera<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Serie de Fichas t\u00e9cnicas que aportan informaci\u00f3n al productor de avellana europea.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Ficha T\u00e9cnica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jaime Guerrero Contreras, Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> P\u00e1gina web<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Enfermedades del Avellano Europeo: Hongos de la semilla<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Serie de Fichas t\u00e9cnicas que aportan informaci\u00f3n al productor de avellana europea.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Ficha T\u00e9cnica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jaime Guerrero Contreras, Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> P\u00e1gina web<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Enfermedades del Avellano Europeo: Hongos de la semilla<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Serie de Fichas t\u00e9cnicas que aportan informaci\u00f3n al productor de avellana europea.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Ficha T\u00e9cnica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jaime Guerrero Contreras, Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> P\u00e1gina web<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Enfermedades del Avellano Europeo: Hongos de poscosecha<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Serie de Fichas t\u00e9cnicas que aportan informaci\u00f3n al productor de avellana europea.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Ficha T\u00e9cnica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jaime Guerrero Contreras, Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> P\u00e1gina web<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Enfermedades del Avellano Europeo: Hongos de poscosecha<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Serie de Fichas t\u00e9cnicas que aportan informaci\u00f3n al productor de avellana europea.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Ficha T\u00e9cnica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jaime Guerrero Contreras, Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> P\u00e1gina web<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Enfermedades del Avellano Europeo: Oidio del avellano Europeo<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Serie de Fichas t\u00e9cnicas que aportan informaci\u00f3n al productor de avellana europea.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Ficha T\u00e9cnica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jaime Guerrero Contreras, Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> P\u00e1gina web<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Enfermedades del Avellano Europeo: Oidio del avellano Europeo<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Serie de Fichas t\u00e9cnicas que aportan informaci\u00f3n al productor de avellana europea.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Ficha T\u00e9cnica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jaime Guerrero Contreras, Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> P\u00e1gina web<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Enfermedades del Avellano Europeo: Tiz\u00f3n bacteriano<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Serie de Fichas t\u00e9cnicas que aportan informaci\u00f3n al productor de avellana europea.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Ficha T\u00e9cnica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jaime Guerrero Contreras, Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> P\u00e1gina web<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Enfermedades del Avellano Europeo: Tiz\u00f3n bacteriano<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Serie de Fichas t\u00e9cnicas que aportan informaci\u00f3n al productor de avellana europea.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Ficha T\u00e9cnica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jaime Guerrero Contreras, Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/www.coes.cl\/wp-content\/uploads\/2017\/11\/Resultado-Primera-Ola-ELSOC.-Modulo-5.-Genero.pdf<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Resultados Primera Ola, Estudio Longitudinal Social de Chile (ELSOC). M\u00f3dulo 5: G\u00e9nero: Brechas y Actitudes. La desigualdad entre hombres y mujeres y los roles de g\u00e9nero<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Resultados Primera Ola Estudio Longitudinal Social de Chile (ELSOC)<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Ana Figueiredo, Gloria Jim\u00e9nez-Moya, Valentina Macarena Paredes Godoy, Alejandro Antonio Gonz\u00e1lez Candia<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/www.coes.cl\/wp-content\/uploads\/2017\/11\/Resultado-Primera-Ola-ELSOC.-Modulo-5.-Genero.pdf<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Resultados Primera Ola, Estudio Longitudinal Social de Chile (ELSOC). M\u00f3dulo 5: G\u00e9nero: Brechas y Actitudes. La desigualdad entre hombres y mujeres y los roles de g\u00e9nero<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Resultados Primera Ola Estudio Longitudinal Social de Chile (ELSOC)<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Ana Figueiredo, Gloria Jim\u00e9nez-Moya, Valentina Macarena Paredes Godoy, Alejandro Antonio Gonz\u00e1lez Candia<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Escuela de Ciencias Agroalimentarias, Animales y Ambientales<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Manual para escritura y presentaci\u00f3n de tesinas<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">MANUAL PARA ESCRITURA Y PRESENTACI\u00d3N DE TESINAS<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Escrito<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Karen Fernanda Mesa Juliani<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Escuela de Ciencias Agroalimentarias, Animales y Ambientales<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Manual para escritura y presentaci\u00f3n de tesinas<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">MANUAL PARA ESCRITURA Y PRESENTACI\u00d3N DE TESINAS<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Escrito<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Karen Fernanda Mesa Juliani<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Cuentos para trabajar Educaci\u00f3n Sexual Integral<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">jajjajaaja<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Cuentos<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">B\u00e1rbara Fernanda D\u00edaz Far\u00edas, Isidora Fuentes., Luc\u00eda Zapata., Daniela Sof\u00eda Jadue Roa, Thiare Galdamez Hernandez, Pamela Alejandra Sep\u00falveda Jim\u00e9nez, Mar\u00eda Jos\u00e9 Gonz\u00e1lez., Mar\u00eda Teresa Sol\u00eds Soto, Mar\u00eda Soledad Burrone Colombino<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Cuentos para trabajar Educaci\u00f3n Sexual Integral<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">jajjajaaja<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Cuentos<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">B\u00e1rbara Fernanda D\u00edaz Far\u00edas, Isidora Fuentes., Luc\u00eda Zapata., Daniela Sof\u00eda Jadue Roa, Thiare Galdamez Hernandez, Pamela Alejandra Sep\u00falveda Jim\u00e9nez, Mar\u00eda Jos\u00e9 Gonz\u00e1lez., Mar\u00eda Teresa Sol\u00eds Soto, Mar\u00eda Soledad Burrone Colombino<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> www.proyectonodo.cl, chile.un.org y sitios web del Programa de las Naciones Unidas para el Desarrollo en Chile (PNUD)<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Comunidades y entornos rurales en Chile. An\u00e1lisis y perspectivas sobre poblaci\u00f3n mayor. Santiago de Chile, Sistema de las Naciones Unidas en Chile.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Programa de las Naciones Unidas para el Desarrollo en Chile (PNUD) la Organizaci\u00f3n de las\r\nNaciones Unidas para la Organizaci\u00f3n y la Agricultura en Chile (FAO) y la Oficina de la Organizaci\u00f3n Internacional del Trabajo (OIT) para el Cono Sur.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Gonzalo Benjam\u00edn Terreros Hern\u00e1ndez<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> www.proyectonodo.cl, chile.un.org y sitios web del Programa de las Naciones Unidas para el Desarrollo en Chile (PNUD)<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Comunidades y entornos rurales en Chile. An\u00e1lisis y perspectivas sobre poblaci\u00f3n mayor. Santiago de Chile, Sistema de las Naciones Unidas en Chile.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Programa de las Naciones Unidas para el Desarrollo en Chile (PNUD) la Organizaci\u00f3n de las\r\nNaciones Unidas para la Organizaci\u00f3n y la Agricultura en Chile (FAO) y la Oficina de la Organizaci\u00f3n Internacional del Trabajo (OIT) para el Cono Sur.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Gonzalo Benjam\u00edn Terreros Hern\u00e1ndez<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Informe Mesa Sistemas Alimentarios Sostenibles y Saludables<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Este informe, el cual elaboramos a partir del trabajo en la Mesa de Sistemas Alimentarios Saludables y Sostenibles, de la Comisi\u00f3n de Desaf\u00edos del Futuro,Ciencia, Tecnolog\u00eda e Innovaci\u00f3n del Senado de Chile, se encuentra en  revisi\u00f3n para su publicaci\u00f3n digital.\r\n\r\nExiste referencia al mismo en el libro: Chile tiene Futuro desde sus Territorios - Comisi\u00f3n Desaf\u00edos del Futuro, Ciencia, Tecnolog\u00eda e Innovaci\u00f3n 2018 -2022: Guido Girardi Lav\u00edn, editor general; Marek Hoehn, Mauricio Amar, David V\u00e1squez, Juan Walker, editores; Santiago de Chile, Ediciones Biblioteca del Congreso Nacional de Chile, 2022, en las p\u00e1ginas 285 a 303, disponible en el siguiente link: https:\/\/consejofuturo.senado.cl\/wp-content\/uploads\/2022\/09\/Chile_tiene_Futuro-.pdf<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Comisi\u00f3n Desaf\u00edos del Futuro, Ciencia, Tecnolog\u00eda e Innovaci\u00f3n del Senado de Chile<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Camila Marta Oda Montecinos<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Informe Mesa Sistemas Alimentarios Sostenibles y Saludables<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Este informe, el cual elaboramos a partir del trabajo en la Mesa de Sistemas Alimentarios Saludables y Sostenibles, de la Comisi\u00f3n de Desaf\u00edos del Futuro,Ciencia, Tecnolog\u00eda e Innovaci\u00f3n del Senado de Chile, se encuentra en  revisi\u00f3n para su publicaci\u00f3n digital.\r\n\r\nExiste referencia al mismo en el libro: Chile tiene Futuro desde sus Territorios - Comisi\u00f3n Desaf\u00edos del Futuro, Ciencia, Tecnolog\u00eda e Innovaci\u00f3n 2018 -2022: Guido Girardi Lav\u00edn, editor general; Marek Hoehn, Mauricio Amar, David V\u00e1squez, Juan Walker, editores; Santiago de Chile, Ediciones Biblioteca del Congreso Nacional de Chile, 2022, en las p\u00e1ginas 285 a 303, disponible en el siguiente link: https:\/\/consejofuturo.senado.cl\/wp-content\/uploads\/2022\/09\/Chile_tiene_Futuro-.pdf<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Comisi\u00f3n Desaf\u00edos del Futuro, Ciencia, Tecnolog\u00eda e Innovaci\u00f3n del Senado de Chile<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Camila Marta Oda Montecinos<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Bases para incorporar compost en la viverizaci\u00f3n de especies nativas en Chile: Pauta T\u00e9cnica\u0094,<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Pauta t\u00e9cnica del FIA<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Propiedad Intelectual bajo el\/los n\u00famero(s) 2023-A-5089.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jorge Felipe Medina Ot\u00e1rola<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Indicadores de salud de suelo en predios hort\u00edcolas de la regi\u00f3n de O\u0092Higgins: evaluaci\u00f3n en funci\u00f3n de distintas pr\u00e1cticas de manejo.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe t\u00e9cnico de difusi\u00f3n de los principales resultados del proyecto FIA EST 2021-605- \u0093Desarrollo de l\u00ednea base para orientar estrategias de sustentabilidad y econom\u00eda circular con foco en salud de suelos hort\u00edcolas de la regi\u00f3n de O'Higgins, desarrollado por UC Davis en colaboraci\u00f3n con Coagricam y la UOH<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Documento t\u00e9cnico difusi\u00f3n UC Davis<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jorge Felipe Medina Ot\u00e1rola<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> COP30<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">&#8220;Econom\u00eda Circular y Cambio Clim\u00e1tico en Chile: Recomendaciones Cient\u00edficas para la Pol\u00edtica P\u00fablica&#8221;<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe t\u00e9cnico-cient\u00edfico que ser\u00e1 presentado en COP30 por la Secretaria T\u00e9cnica del Comit\u00e9 Cient\u00edfico Asesor de Cambio Clim\u00e1tico del Ministerio de Ciencia, Tecnolog\u00eda, Conocimiento e Innovaci\u00f3n.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jorge Felipe Medina Ot\u00e1rola<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Bases para incorporar compost en la viverizaci\u00f3n de especies nativas en Chile: Pauta T\u00e9cnica\u0094,<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Pauta t\u00e9cnica del FIA<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Propiedad Intelectual bajo el\/los n\u00famero(s) 2023-A-5089.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jorge Felipe Medina Ot\u00e1rola<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Indicadores de salud de suelo en predios hort\u00edcolas de la regi\u00f3n de O\u0092Higgins: evaluaci\u00f3n en funci\u00f3n de distintas pr\u00e1cticas de manejo.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe t\u00e9cnico de difusi\u00f3n de los principales resultados del proyecto FIA EST 2021-605- \u0093Desarrollo de l\u00ednea base para orientar estrategias de sustentabilidad y econom\u00eda circular con foco en salud de suelos hort\u00edcolas de la regi\u00f3n de O'Higgins, desarrollado por UC Davis en colaboraci\u00f3n con Coagricam y la UOH<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Documento t\u00e9cnico difusi\u00f3n UC Davis<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jorge Felipe Medina Ot\u00e1rola<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> COP30<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">&#8220;Econom\u00eda Circular y Cambio Clim\u00e1tico en Chile: Recomendaciones Cient\u00edficas para la Pol\u00edtica P\u00fablica&#8221;<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe t\u00e9cnico-cient\u00edfico que ser\u00e1 presentado en COP30 por la Secretaria T\u00e9cnica del Comit\u00e9 Cient\u00edfico Asesor de Cambio Clim\u00e1tico del Ministerio de Ciencia, Tecnolog\u00eda, Conocimiento e Innovaci\u00f3n.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jorge Felipe Medina Ot\u00e1rola<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Proceedings of the 17th Pan-American Conference on Soil Mechanics and Geotechnical Engineering (XVII PCSMGE), and 2nd Latin-American Regional Conference of the International Association for Engineering Geology and the Environment (IAEG),<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Shallow-seated landslide susceptibility and hazard assessment in volcanic edifices from an engineering geological approach: Case of study Llaima volcano<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">chrome-extension:\/\/efaidnbmnnnibpcajpcglclefindmkaj\/https:\/\/www.issmge.org\/uploads\/publications\/84\/130\/FV_419_-_MT_4_-_FV.pdf<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Proceedings<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Alejandra Serey Amador, Jorge Eduardo Romero Moyano, B. Salinas, A. Salgado, Ivo Fustos-Toribio, Demian Byron Trigo Cruz, Laura Becerril Carretero, Marisol Lara<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Proceedings of the 17th Pan-American Conference on Soil Mechanics and Geotechnical Engineering (XVII PCSMGE), and 2nd Latin-American Regional Conference of the International Association for Engineering Geology and the Environment (IAEG),<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Shallow-seated landslide susceptibility and hazard assessment in volcanic edifices from an engineering geological approach: Case of study Llaima volcano<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">chrome-extension:\/\/efaidnbmnnnibpcajpcglclefindmkaj\/https:\/\/www.issmge.org\/uploads\/publications\/84\/130\/FV_419_-_MT_4_-_FV.pdf<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Proceedings<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Alejandra Serey Amador, Jorge Eduardo Romero Moyano, B. Salinas, A. Salgado, Ivo Fustos-Toribio, Demian Byron Trigo Cruz, Laura Becerril Carretero, Marisol Lara<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Estudio para la evaluaci\u00f3n de variables que impactan el resultado de las mujeres en la etapa de an\u00e1lisis curricular (P1) en concursos del Sistema de Alta Direcci\u00f3n P\u00fablica<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe del estudio pedido por el Servicio Civil a la Universidad de O'Higgins y realizado por Andrea Canales y Ana Figueiredo sobre variables que impactan el resultado de las mujeres en la etapa de an\u00e1lisis curricular (P1) en concursos del Sistema de Alta Direcci\u00f3n P\u00fablica.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Andrea Ignacia Canales Guti\u00e9rrez, Ana Figueiredo, Kevin Carrasco, Diego Andr\u00e9s Garrido Delgado<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Estudio para la evaluaci\u00f3n de variables que impactan el resultado de las mujeres en la etapa de an\u00e1lisis curricular (P1) en concursos del Sistema de Alta Direcci\u00f3n P\u00fablica<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe del estudio pedido por el Servicio Civil a la Universidad de O'Higgins y realizado por Andrea Canales y Ana Figueiredo sobre variables que impactan el resultado de las mujeres en la etapa de an\u00e1lisis curricular (P1) en concursos del Sistema de Alta Direcci\u00f3n P\u00fablica.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Andrea Ignacia Canales Guti\u00e9rrez, Ana Figueiredo, Kevin Carrasco, Diego Andr\u00e9s Garrido Delgado<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Desigualdad y Territorio en los pueblos Ind\u00edgenas en Chile: un diagn\u00f3stico latinoamericano y propuestas de investigaci\u00f3n desde Rimisp<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Serie Documentos de Trabajo N\u00b0206, Grupo de Trabajo Desarrollo con Cohesi\u00f3n Territorial, Programa Cohesi\u00f3n Territorial para el Desarrollo. Rimisp, Santiago, Chile. Disponible aqu\u00ed: https:\/\/rimisp.org\/wp-content\/files_mf\/1486404340206DesigualdadyTerritorioenlospueblos.pdf<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">David L\u00f3pez Moreno, Constanza Christian, Milena Vargas, Mariana Calcagni, Ricardo Sebasti\u00e1n Fuentealba Fuentes<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Desigualdad y Territorio en los pueblos Ind\u00edgenas en Chile: un diagn\u00f3stico latinoamericano y propuestas de investigaci\u00f3n desde Rimisp<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Serie Documentos de Trabajo N\u00b0206, Grupo de Trabajo Desarrollo con Cohesi\u00f3n Territorial, Programa Cohesi\u00f3n Territorial para el Desarrollo. Rimisp, Santiago, Chile. Disponible aqu\u00ed: https:\/\/rimisp.org\/wp-content\/files_mf\/1486404340206DesigualdadyTerritorioenlospueblos.pdf<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">David L\u00f3pez Moreno, Constanza Christian, Milena Vargas, Mariana Calcagni, Ricardo Sebasti\u00e1n Fuentealba Fuentes<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Ciudades, territorios y desarrollo rural en la Regi\u00f3n de O\u0092Higgins.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Serie Documentos de Trabajo N\u00b0104, Programa Din\u00e1micas Territoriales Rurales. Rimisp, Santiago, Chile. Disponible aqu\u00ed: https:\/\/www.rimisp.org\/wp-content\/files_mf\/13662879021042012Ciudades_territorios_y_desarrollo_rural_regionOHigginsBroFuentealba.pdf<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Naim Bro, Ricardo Sebasti\u00e1n Fuentealba Fuentes<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Territorios funcionales en Chile.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Serie Documentos de Trabajo N\u00b0102, Programa Din\u00e1micas Territoriales Rurales. Rimisp, Santiago, Chile. Disponible aqu\u00ed: https:\/\/www.rimisp.org\/wp-content\/files_mf\/1366288203N1022011_TerritoriosFuncionalesChile_BerdegueJaraFuentealbaTohaetal.pdf<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Julio A. Berdegu\u00e9, Benjam\u00edn Jara Valencia, Ricardo Sebasti\u00e1n Fuentealba Fuentes, Jaime Toh\u00e1, Felix Modrego Benito, Alejandro Schejtman, Naim Bro<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Ciudades, territorios y desarrollo rural en la Regi\u00f3n de O\u0092Higgins.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Serie Documentos de Trabajo N\u00b0104, Programa Din\u00e1micas Territoriales Rurales. Rimisp, Santiago, Chile. Disponible aqu\u00ed: https:\/\/www.rimisp.org\/wp-content\/files_mf\/13662879021042012Ciudades_territorios_y_desarrollo_rural_regionOHigginsBroFuentealba.pdf<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Naim Bro, Ricardo Sebasti\u00e1n Fuentealba Fuentes<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">The spatial politics of hazard warnings signs: an incomplete photo comparison of two countries<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Escrito en el contexto de la revista Wicked Stars: A Zin to Trouble Disaster Studies.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Ricardo Sebasti\u00e1n Fuentealba Fuentes<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Territorios funcionales en Chile.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Serie Documentos de Trabajo N\u00b0102, Programa Din\u00e1micas Territoriales Rurales. Rimisp, Santiago, Chile. Disponible aqu\u00ed: https:\/\/www.rimisp.org\/wp-content\/files_mf\/1366288203N1022011_TerritoriosFuncionalesChile_BerdegueJaraFuentealbaTohaetal.pdf<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Julio A. Berdegu\u00e9, Benjam\u00edn Jara Valencia, Ricardo Sebasti\u00e1n Fuentealba Fuentes, Jaime Toh\u00e1, Felix Modrego Benito, Alejandro Schejtman, Naim Bro<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">The spatial politics of hazard warnings signs: an incomplete photo comparison of two countries<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Escrito en el contexto de la revista Wicked Stars: A Zin to Trouble Disaster Studies.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Ricardo Sebasti\u00e1n Fuentealba Fuentes<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Interno Unidades de Gesti\u00f3n del Orden P\u00fablico de Carabineros de Chile<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Entendiendo a las multitudes desde una perspectiva psicol\u00f3gica<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Texto de estudio<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Patricio Saavedra Morales<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> 10.31234\/osf.io\/rm7jg<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Beyond peaceful protest: When non-participants support violence against the police<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Paper en formato pre-print<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Pre-Print<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Patricio Saavedra Morales, John Drury<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> http:\/\/dx.doi.org\/10.31234\/osf.io\/753ph<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Solidarity with those who hit the streets: Public opinion and support for protesters&#8217; self- defence actions when the right to protest is restricted<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Pre-Print<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Patricio Saavedra Morales, John Drury<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> 10.13140\/RG.2.2.11363.16168\/1<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Authorities\u0092 role in the (de-)escalation of political conflicts<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Call for papers (Special Issue) del Peace and Conflict: Journal of Peace Psychology<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Call for papers Special Issue<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Patricio Saavedra Morales, Maria Chayinska, \u00d6zden Melis Ulu&#287;, Edmund Cheng, Matt Radburn<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Interno Unidades de Gesti\u00f3n del Orden P\u00fablico de Carabineros de Chile<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Entendiendo a las multitudes desde una perspectiva psicol\u00f3gica<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Texto de estudio<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Patricio Saavedra Morales<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> 10.31234\/osf.io\/rm7jg<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Beyond peaceful protest: When non-participants support violence against the police<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Paper en formato pre-print<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Pre-Print<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Patricio Saavedra Morales, John Drury<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> http:\/\/dx.doi.org\/10.31234\/osf.io\/753ph<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Solidarity with those who hit the streets: Public opinion and support for protesters&#8217; self- defence actions when the right to protest is restricted<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Pre-Print<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Patricio Saavedra Morales, John Drury<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> 10.13140\/RG.2.2.11363.16168\/1<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Authorities\u0092 role in the (de-)escalation of political conflicts<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Call for papers (Special Issue) del Peace and Conflict: Journal of Peace Psychology<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Call for papers Special Issue<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Patricio Saavedra Morales, Maria Chayinska, \u00d6zden Melis Ulu&#287;, Edmund Cheng, Matt Radburn<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Rese\u00f1a libro<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Rese\u00f1a del libro Discursive processes of intergenerational transmission of recent history: (Re)making our past, por Mariana Achugar<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Journal of Language and Politics<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Carolina P\u00e9rez Arredondo<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Rese\u00f1a libro<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Rese\u00f1a del libro Discursive processes of intergenerational transmission of recent history: (Re)making our past, por Mariana Achugar<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Journal of Language and Politics<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Carolina P\u00e9rez Arredondo<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Interna ANID<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Evaluador ANID Fondecyt Iniciaci\u00f3n 2025.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Interna del grupo de estudio en Matem\u00e1ticas ANID<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe de evaluaci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Andr\u00e9s Jahir Z\u00fa\u00f1iga Munizaga<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Interna ANID<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Evaluador ANID Fondecyt Iniciaci\u00f3n 2025.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Interna del grupo de estudio en Matem\u00e1ticas ANID<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe de evaluaci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Andr\u00e9s Jahir Z\u00fa\u00f1iga Munizaga<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Interna<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Manual para escritura y presentaci\u00f3n de tesinas (ECA3)<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Manual de Tesis de pregrado ECA3<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Camila Soto, Catalina Javiera Pinto Palacios, Nicolas Osvaldo Quiroga Barrera, Paula Andrea Irles Ivanac, Paula Macarena Toro Mujica, Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Interna<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Manual para escritura y presentaci\u00f3n de tesinas (ECA3)<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Manual de Tesis de pregrado ECA3<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Camila Soto, Catalina Javiera Pinto Palacios, Nicolas Osvaldo Quiroga Barrera, Paula Andrea Irles Ivanac, Paula Macarena Toro Mujica, Set Madian P\u00e9rez Fuentealba<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Cuentos para trabajar Educaci\u00f3n Sexual Integral<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">jajjajaaja<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Cuentos<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">B\u00e1rbara Fernanda D\u00edaz Far\u00edas, Isidora Fuentes., Luc\u00eda Zapata., Daniela Sof\u00eda Jadue Roa, Thiare Galdamez Hernandez, Pamela Alejandra Sep\u00falveda Jim\u00e9nez, Mar\u00eda Jos\u00e9 Gonz\u00e1lez., Mar\u00eda Teresa Sol\u00eds Soto, Mar\u00eda Soledad Burrone Colombino<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Cuentos para trabajar Educaci\u00f3n Sexual Integral<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">jajjajaaja<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Cuentos<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">B\u00e1rbara Fernanda D\u00edaz Far\u00edas, Isidora Fuentes., Luc\u00eda Zapata., Daniela Sof\u00eda Jadue Roa, Thiare Galdamez Hernandez, Pamela Alejandra Sep\u00falveda Jim\u00e9nez, Mar\u00eda Jos\u00e9 Gonz\u00e1lez., Mar\u00eda Teresa Sol\u00eds Soto, Mar\u00eda Soledad Burrone Colombino<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/drive.google.com\/file\/d\/1l_mW84pYiSt1Aue0xxaZtgPF1LFS8XCl\/view<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Impacto Psicosocial de COVID-19 Chile. Primer Reporte de Resultados<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Autores: Burrone, Mar\u00eda Soledad; Solis-Soto, Mar\u00eda Teresa; Arrossi, Silvina;\r\nRamos, Silvina; Ahumada Danay;\r\nAlvarado, Ruben; Barrientos Cabeza, Catalina; Basagoitia, Armando;\r\nIrrar\u00e1zaval, Mat\u00edas; Leniz, Irene;\r\nMolina N\u00fa\u00f1ez, Fabiola; Reginatto, Gabriel; Rinc\u00f3n Gonz\u00e1lez, Paulina Paz;\r\nTapia Mu\u00f1oz, Thamara; Vald\u00e9s, Daniela;\r\nValenzuela, Silva Paulina y Villagran, Loreto<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Primer reporte de resultados: Impacto psicosocial de Covid-19 Chile<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Mar\u00eda Soledad Burrone Colombino, Mar\u00eda Teresa Sol\u00eds Soto, Silvina Arrosi, Silvina Ramos, Danay Ahumada, Rub\u00e9n Alvarado, Catalina Barrientos Cabezas, Armando Basagoitia, Mat\u00edas Irrar\u00e1zaval, Mar\u00eda Irene Leniz Eguiguren, Fabiola Andrea Molina N\u00fa\u00f1ez, Gabriel Reginatto, Paulina Paz Rinc\u00f3n, Daniela Vald\u00e9s, Paulina Valenzuela Silva, Loreto Villagr\u00e1n Valenzuela, Thamara Tapia<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/drive.google.com\/file\/d\/1l_mW84pYiSt1Aue0xxaZtgPF1LFS8XCl\/view<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Impacto Psicosocial de COVID-19 Chile. Primer Reporte de Resultados<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Autores: Burrone, Mar\u00eda Soledad; Solis-Soto, Mar\u00eda Teresa; Arrossi, Silvina;\r\nRamos, Silvina; Ahumada Danay;\r\nAlvarado, Ruben; Barrientos Cabeza, Catalina; Basagoitia, Armando;\r\nIrrar\u00e1zaval, Mat\u00edas; Leniz, Irene;\r\nMolina N\u00fa\u00f1ez, Fabiola; Reginatto, Gabriel; Rinc\u00f3n Gonz\u00e1lez, Paulina Paz;\r\nTapia Mu\u00f1oz, Thamara; Vald\u00e9s, Daniela;\r\nValenzuela, Silva Paulina y Villagran, Loreto<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Primer reporte de resultados: Impacto psicosocial de Covid-19 Chile<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Mar\u00eda Soledad Burrone Colombino, Mar\u00eda Teresa Sol\u00eds Soto, Silvina Arrosi, Silvina Ramos, Danay Ahumada, Rub\u00e9n Alvarado, Catalina Barrientos Cabezas, Armando Basagoitia, Mat\u00edas Irrar\u00e1zaval, Mar\u00eda Irene Leniz Eguiguren, Fabiola Andrea Molina N\u00fa\u00f1ez, Gabriel Reginatto, Paulina Paz Rinc\u00f3n, Daniela Vald\u00e9s, Paulina Valenzuela Silva, Loreto Villagr\u00e1n Valenzuela, Thamara Tapia<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Stop Acoso<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Publicaci\u00f3n datos regionales de la encuesta Stop Acoso.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe Regional<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Roc\u00edo Angulo<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Stop Acoso<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Publicaci\u00f3n datos regionales de la encuesta Stop Acoso.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe Regional<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Roc\u00edo Angulo<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Resultados Primera Ola, Estudio Longitudinal Social de Chile (ELSOC). M\u00f3dulo 2: Conflicto Social. Los motivos de la justificaci\u00f3n de la violencia en Chile<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Ana Figueiredo, Monica Gerber, H\u00e9ctor Carvacho, Gloria Jim\u00e9nez-Moya, Crist\u00f3bal Moya, Bel\u00e9n \u00c1lvarez<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Resultados Primera Ola, Estudio Longitudinal Social de Chile (ELSOC). M\u00f3dulo 2: Conflicto Social. Los motivos de la justificaci\u00f3n de la violencia en Chile<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Ana Figueiredo, Monica Gerber, H\u00e9ctor Carvacho, Gloria Jim\u00e9nez-Moya, Crist\u00f3bal Moya, Bel\u00e9n \u00c1lvarez<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/www.coes.cl\/wp-content\/uploads\/2017\/11\/Resultado-Primera-Ola-ELSOC.-Modulo-5.-Genero.pdf<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Resultados Primera Ola, Estudio Longitudinal Social de Chile (ELSOC). M\u00f3dulo 5: G\u00e9nero: Brechas y Actitudes. La desigualdad entre hombres y mujeres y los roles de g\u00e9nero<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Resultados Primera Ola Estudio Longitudinal Social de Chile (ELSOC)<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Ana Figueiredo, Gloria Jim\u00e9nez-Moya, Valentina Macarena Paredes Godoy, Alejandro Antonio Gonz\u00e1lez Candia<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/www.coes.cl\/wp-content\/uploads\/2017\/11\/Resultado-Primera-Ola-ELSOC.-Modulo-5.-Genero.pdf<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Resultados Primera Ola, Estudio Longitudinal Social de Chile (ELSOC). M\u00f3dulo 5: G\u00e9nero: Brechas y Actitudes. La desigualdad entre hombres y mujeres y los roles de g\u00e9nero<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Resultados Primera Ola Estudio Longitudinal Social de Chile (ELSOC)<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Ana Figueiredo, Gloria Jim\u00e9nez-Moya, Valentina Macarena Paredes Godoy, Alejandro Antonio Gonz\u00e1lez Candia<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Cultural factors: National cultural factors associated with processes of radicalisation leading to terrorism.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Valentim, J. P., Figueiredo, A., & Duarte, J., & van Hemert, D. (2013). Cultural factors: National cultural factors associated with processes of radicalisation leading to terrorism. Focus Document for the FP7 Project SAFIRE. Retirado de: http:\/\/www.safire-project-results.eu\/documents\/focus\/15.pdf<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Ana Figueiredo<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">National cultural factors associated to processes of violent radicalisation and terrorism. In Synthesis report on the results from WP 3 &#038; 4. Final deliverables for the FP7 Project SAFIRE.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Valentim, J. P., Figueiredo, A., & Duarte, J., & van Hemert, D. (2013). National cultural factors associated to processes of violent radicalisation and terrorism. In Synthesis report on the results from WP 3 & 4. Final deliverables for the FP7 Project SAFIRE. Retirado de: http:\/\/www.safire-project-results.eu\/documents\/deliverables\/3-4-modeling-culture-indicators-and-intervention-evaluation.pdf<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Ana Figueiredo<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Cultural factors: National cultural factors associated with processes of radicalisation leading to terrorism.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Valentim, J. P., Figueiredo, A., & Duarte, J., & van Hemert, D. (2013). Cultural factors: National cultural factors associated with processes of radicalisation leading to terrorism. Focus Document for the FP7 Project SAFIRE. Retirado de: http:\/\/www.safire-project-results.eu\/documents\/focus\/15.pdf<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Ana Figueiredo<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">National cultural factors associated to processes of violent radicalisation and terrorism. In Synthesis report on the results from WP 3 &#038; 4. Final deliverables for the FP7 Project SAFIRE.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Valentim, J. P., Figueiredo, A., & Duarte, J., & van Hemert, D. (2013). National cultural factors associated to processes of violent radicalisation and terrorism. In Synthesis report on the results from WP 3 & 4. Final deliverables for the FP7 Project SAFIRE. Retirado de: http:\/\/www.safire-project-results.eu\/documents\/deliverables\/3-4-modeling-culture-indicators-and-intervention-evaluation.pdf<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Ana Figueiredo<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Estudio para la evaluaci\u00f3n de variables que impactan el resultado de las mujeres en la etapa de an\u00e1lisis curricular (P1) en concursos del Sistema de Alta Direcci\u00f3n P\u00fablica<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe del estudio pedido por el Servicio Civil a la Universidad de O'Higgins y realizado por Andrea Canales y Ana Figueiredo sobre variables que impactan el resultado de las mujeres en la etapa de an\u00e1lisis curricular (P1) en concursos del Sistema de Alta Direcci\u00f3n P\u00fablica.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Andrea Ignacia Canales Guti\u00e9rrez, Ana Figueiredo, Kevin Carrasco, Diego Andr\u00e9s Garrido Delgado<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Estudio para la evaluaci\u00f3n de variables que impactan el resultado de las mujeres en la etapa de an\u00e1lisis curricular (P1) en concursos del Sistema de Alta Direcci\u00f3n P\u00fablica<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe del estudio pedido por el Servicio Civil a la Universidad de O'Higgins y realizado por Andrea Canales y Ana Figueiredo sobre variables que impactan el resultado de las mujeres en la etapa de an\u00e1lisis curricular (P1) en concursos del Sistema de Alta Direcci\u00f3n P\u00fablica.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Andrea Ignacia Canales Guti\u00e9rrez, Ana Figueiredo, Kevin Carrasco, Diego Andr\u00e9s Garrido Delgado<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/coes.cl\/wp-content\/uploads\/Radiografia-Cohesion-social-2016-2023-version-completa.pdf<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Radiograf\u00eda de la Cohesi\u00f3n Social en Chile 2016-2023 &#8211; Versi\u00f3n Completa<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Roberto Gonzalez, Ana Figueiredo, Matias Bargsted, Daniel Miranda<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/coes.cl\/wp-content\/uploads\/Radiografia-Cohesion-social-2016-2023-version-completa.pdf<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Radiograf\u00eda de la Cohesi\u00f3n Social en Chile 2016-2023 &#8211; Versi\u00f3n Completa<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Roberto Gonzalez, Ana Figueiredo, Matias Bargsted, Daniel Miranda<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Radiograf\u00eda del Cambio Social en Chile 2016-2022<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe de los resultados del estudio ELSOC 2016-2022.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">https:\/\/radiografia-cambio-social-2016-2022.netlify.app\/<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Roberto Gonzalez, Ana Figueiredo, Matias Bargsted, Daniel Miranda<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Radiograf\u00eda del Cambio Social en Chile 2016-2022<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe de los resultados del estudio ELSOC 2016-2022.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">https:\/\/radiografia-cambio-social-2016-2022.netlify.app\/<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Roberto Gonzalez, Ana Figueiredo, Matias Bargsted, Daniel Miranda<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/iris.paho.org\/bitstream\/handle\/10665.2\/55563\/OPSNMHMHCOVID-19220001_spa.pdf?sequence=1&isAllowed=y<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">The COVID-19 HEalth caRe wOrkErs Study (HEROES). Informe Regional de las Am\u00e9ricas<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Co-investigadora que form\u00f3 parte del equipo que desarroll\u00f3 este estudio.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Documento<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Mar\u00eda Soledad Burrone Colombino<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/iris.paho.org\/bitstream\/handle\/10665.2\/55563\/OPSNMHMHCOVID-19220001_spa.pdf?sequence=1&isAllowed=y<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">The COVID-19 HEalth caRe wOrkErs Study (HEROES). Informe Regional de las Am\u00e9ricas<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Co-investigadora que form\u00f3 parte del equipo que desarroll\u00f3 este estudio.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Documento<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Mar\u00eda Soledad Burrone Colombino<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/drive.google.com\/file\/d\/19WjaT6VIAewyEFQheGkGrej782albsEC\/view<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Foros para el an\u00e1lisis de las implicancias de la Ley 21.331 \u0093Del Reconocimiento y Protecci\u00f3n de los Derechos de las Personas en la Atenci\u00f3n de Salud Mental<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Coordinadora del proceso de sistematizaci\u00f3n en el \u0093Ciclo de Foros para el An\u00e1lisis de las implicancias de la Ley 21.331 de reconocimiento y protecci\u00f3n de los derechos de las personas en la atenci\u00f3n de salud mental\"<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe final de los ciclos de foro para el an\u00e1lisis de las implicancias de la Ley 21.331 \u0093Del Reconocimiento y Protecci\u00f3n de los Derechos de las Personas en la Atenci\u00f3n de Salud Mental\u0094<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Olga Toro Devia, Roc\u00edo Mu\u00f1oz Le\u00f3n, Ver\u00f3nica Monreal, Tomicic Alemka, Mar\u00eda Ang\u00e9lica Benavides, Mar\u00eda Soledad Burrone Colombino, Jimena Carrasco, H\u00e9ctor Duque<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/drive.google.com\/file\/d\/19WjaT6VIAewyEFQheGkGrej782albsEC\/view<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Foros para el an\u00e1lisis de las implicancias de la Ley 21.331 \u0093Del Reconocimiento y Protecci\u00f3n de los Derechos de las Personas en la Atenci\u00f3n de Salud Mental<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Coordinadora del proceso de sistematizaci\u00f3n en el \u0093Ciclo de Foros para el An\u00e1lisis de las implicancias de la Ley 21.331 de reconocimiento y protecci\u00f3n de los derechos de las personas en la atenci\u00f3n de salud mental\"<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe final de los ciclos de foro para el an\u00e1lisis de las implicancias de la Ley 21.331 \u0093Del Reconocimiento y Protecci\u00f3n de los Derechos de las Personas en la Atenci\u00f3n de Salud Mental\u0094<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Olga Toro Devia, Roc\u00edo Mu\u00f1oz Le\u00f3n, Ver\u00f3nica Monreal, Tomicic Alemka, Mar\u00eda Ang\u00e9lica Benavides, Mar\u00eda Soledad Burrone Colombino, Jimena Carrasco, H\u00e9ctor Duque<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/www.colegiomedico.cl\/wp-content\/uploads\/2021\/04\/4to-informe.pdf<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">El impacto de la pandemia de Covid-19 en la salud mental de los trabajadores en los servicios de salud. Informe preliminar N\u00b0 4 Chile. Condiciones Laborales<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">https:\/\/www.colegiomedico.cl\/wp-content\/uploads\/2021\/04\/4to-informe.pdf<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe preliminar<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Sebastian Villarroel, Gonzalo Cuadra, Mar\u00eda Soledad Burrone Colombino<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/www.colegiomedico.cl\/wp-content\/uploads\/2021\/04\/4to-informe.pdf<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">El impacto de la pandemia de Covid-19 en la salud mental de los trabajadores en los servicios de salud. Informe preliminar N\u00b0 4 Chile. Condiciones Laborales<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">https:\/\/www.colegiomedico.cl\/wp-content\/uploads\/2021\/04\/4to-informe.pdf<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe preliminar<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Sebastian Villarroel, Gonzalo Cuadra, Mar\u00eda Soledad Burrone Colombino<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> http:\/\/www.socialesudec.cl\/wp-content\/uploads\/2020\/05\/Gu%C3%ADa-Orientaciones-T%C3%A9cnicas-en-Salud-Mental-CTCI-Centro-Sur.pdf<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Gu\u00eda de Orientaciones t\u00e9cnicas para la Salud Mental en pandemia<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Co-autores:\r\nBurrone, Mar\u00eda Soledad\r\nChand\u00eda Garrido, Gerardo\r\nOda Montecinos, Camila\r\nOyanadel V\u00e9liz, Cristian\r\nRinc\u00f3n Gonz\u00e1lez, Paulina<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Gu\u00eda de Orientaciones t\u00e9cnicas para la Salud Mental en pandemia<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Mar\u00eda Soledad Burrone Colombino, Gerardo Chand\u00eda Garrido, Cristian Oyanadel V\u00e9liz, Paulina Rinc\u00f3n Gonz\u00e1lez<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> http:\/\/www.socialesudec.cl\/wp-content\/uploads\/2020\/05\/Gu%C3%ADa-Orientaciones-T%C3%A9cnicas-en-Salud-Mental-CTCI-Centro-Sur.pdf<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Gu\u00eda de Orientaciones t\u00e9cnicas para la Salud Mental en pandemia<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Co-autores:\r\nBurrone, Mar\u00eda Soledad\r\nChand\u00eda Garrido, Gerardo\r\nOda Montecinos, Camila\r\nOyanadel V\u00e9liz, Cristian\r\nRinc\u00f3n Gonz\u00e1lez, Paulina<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Gu\u00eda de Orientaciones t\u00e9cnicas para la Salud Mental en pandemia<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Mar\u00eda Soledad Burrone Colombino, Gerardo Chand\u00eda Garrido, Cristian Oyanadel V\u00e9liz, Paulina Rinc\u00f3n Gonz\u00e1lez<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/drive.google.com\/file\/d\/1l_mW84pYiSt1Aue0xxaZtgPF1LFS8XCl\/view<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Impacto Psicosocial de COVID-19 Chile. Primer Reporte de Resultados<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Autores: Burrone, Mar\u00eda Soledad; Solis-Soto, Mar\u00eda Teresa; Arrossi, Silvina;\r\nRamos, Silvina; Ahumada Danay;\r\nAlvarado, Ruben; Barrientos Cabeza, Catalina; Basagoitia, Armando;\r\nIrrar\u00e1zaval, Mat\u00edas; Leniz, Irene;\r\nMolina N\u00fa\u00f1ez, Fabiola; Reginatto, Gabriel; Rinc\u00f3n Gonz\u00e1lez, Paulina Paz;\r\nTapia Mu\u00f1oz, Thamara; Vald\u00e9s, Daniela;\r\nValenzuela, Silva Paulina y Villagran, Loreto<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Primer reporte de resultados: Impacto psicosocial de Covid-19 Chile<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Mar\u00eda Soledad Burrone Colombino, Mar\u00eda Teresa Sol\u00eds Soto, Silvina Arrosi, Silvina Ramos, Danay Ahumada, Rub\u00e9n Alvarado, Catalina Barrientos Cabezas, Armando Basagoitia, Mat\u00edas Irrar\u00e1zaval, Mar\u00eda Irene Leniz Eguiguren, Fabiola Andrea Molina N\u00fa\u00f1ez, Gabriel Reginatto, Paulina Paz Rinc\u00f3n, Daniela Vald\u00e9s, Paulina Valenzuela Silva, Loreto Villagr\u00e1n Valenzuela, Thamara Tapia<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/drive.google.com\/file\/d\/1l_mW84pYiSt1Aue0xxaZtgPF1LFS8XCl\/view<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Impacto Psicosocial de COVID-19 Chile. Primer Reporte de Resultados<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Autores: Burrone, Mar\u00eda Soledad; Solis-Soto, Mar\u00eda Teresa; Arrossi, Silvina;\r\nRamos, Silvina; Ahumada Danay;\r\nAlvarado, Ruben; Barrientos Cabeza, Catalina; Basagoitia, Armando;\r\nIrrar\u00e1zaval, Mat\u00edas; Leniz, Irene;\r\nMolina N\u00fa\u00f1ez, Fabiola; Reginatto, Gabriel; Rinc\u00f3n Gonz\u00e1lez, Paulina Paz;\r\nTapia Mu\u00f1oz, Thamara; Vald\u00e9s, Daniela;\r\nValenzuela, Silva Paulina y Villagran, Loreto<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Primer reporte de resultados: Impacto psicosocial de Covid-19 Chile<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Mar\u00eda Soledad Burrone Colombino, Mar\u00eda Teresa Sol\u00eds Soto, Silvina Arrosi, Silvina Ramos, Danay Ahumada, Rub\u00e9n Alvarado, Catalina Barrientos Cabezas, Armando Basagoitia, Mat\u00edas Irrar\u00e1zaval, Mar\u00eda Irene Leniz Eguiguren, Fabiola Andrea Molina N\u00fa\u00f1ez, Gabriel Reginatto, Paulina Paz Rinc\u00f3n, Daniela Vald\u00e9s, Paulina Valenzuela Silva, Loreto Villagr\u00e1n Valenzuela, Thamara Tapia<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/www.criticaltime.org\/wp-content\/uploads\/2014\/05\/CTI-TS-Manual-Spanish-version.pdf<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">CTI-TS Manual de Capacitaci\u00f3n<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">CTI-TS Manual de Capacitacion\r\n54-horas de formaci\u00f3n (Pares [PSW], Trabajadores comunitarios [CMHW)], Supervisora de investigaci\u00f3n, Coordinador\/a del trabajo de campo)\r\n\r\nAutores: Sarah Conover y Maria E. Restrepo-Toro\r\n\r\nCollaborators:\r\nMaria Cecilia Carvalho\r\nSara Schilling\r\nMonika Karazja\r\nEzra Susser\r\nElie Valencia\r\nRuben Alvarado\r\nMart\u00edn Agrest\r\nPeter Stastny\r\nAlberto Minoletti\r\nJessie Whitfield\r\nMar\u00eda Soledad Burrone<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Manual de capacitaci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Sarah Conover, Maria E. Restrepo-Toro, Maria Cecilia Carvalho, Sara Schilling, Monika Karazja, Ezra Susser, Eliecer Valencia, Rub\u00e9n Alvarado, Mart\u00edn Agrest., Peter Stastny, Alberto Minoletti., Jessie Whitfield, Mar\u00eda Soledad Burrone Colombino<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/www.criticaltime.org\/wp-content\/uploads\/2014\/05\/CTI-TS-Manual-Spanish-version.pdf<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">CTI-TS Manual de Capacitaci\u00f3n<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">CTI-TS Manual de Capacitacion\r\n54-horas de formaci\u00f3n (Pares [PSW], Trabajadores comunitarios [CMHW)], Supervisora de investigaci\u00f3n, Coordinador\/a del trabajo de campo)\r\n\r\nAutores: Sarah Conover y Maria E. Restrepo-Toro\r\n\r\nCollaborators:\r\nMaria Cecilia Carvalho\r\nSara Schilling\r\nMonika Karazja\r\nEzra Susser\r\nElie Valencia\r\nRuben Alvarado\r\nMart\u00edn Agrest\r\nPeter Stastny\r\nAlberto Minoletti\r\nJessie Whitfield\r\nMar\u00eda Soledad Burrone<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Manual de capacitaci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Sarah Conover, Maria E. Restrepo-Toro, Maria Cecilia Carvalho, Sara Schilling, Monika Karazja, Ezra Susser, Eliecer Valencia, Rub\u00e9n Alvarado, Mart\u00edn Agrest., Peter Stastny, Alberto Minoletti., Jessie Whitfield, Mar\u00eda Soledad Burrone Colombino<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Cuentos para trabajar Educaci\u00f3n Sexual Integral<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">jajjajaaja<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Cuentos<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">B\u00e1rbara Fernanda D\u00edaz Far\u00edas, Isidora Fuentes., Luc\u00eda Zapata., Daniela Sof\u00eda Jadue Roa, Thiare Galdamez Hernandez, Pamela Alejandra Sep\u00falveda Jim\u00e9nez, Mar\u00eda Jos\u00e9 Gonz\u00e1lez., Mar\u00eda Teresa Sol\u00eds Soto, Mar\u00eda Soledad Burrone Colombino<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Cuentos para trabajar Educaci\u00f3n Sexual Integral<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">jajjajaaja<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Cuentos<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">B\u00e1rbara Fernanda D\u00edaz Far\u00edas, Isidora Fuentes., Luc\u00eda Zapata., Daniela Sof\u00eda Jadue Roa, Thiare Galdamez Hernandez, Pamela Alejandra Sep\u00falveda Jim\u00e9nez, Mar\u00eda Jos\u00e9 Gonz\u00e1lez., Mar\u00eda Teresa Sol\u00eds Soto, Mar\u00eda Soledad Burrone Colombino<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/www.uestatales.cl\/cue\/sites\/default\/files\/Clima%20de%20Diversidad%20e%20Inclusi%C3%B3n%20en%20las%20universidades%20estatales_0.pdf<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Clima de diversidad e inclusi\u00f3n en Universidades Estatales, Barreras y Facilitadores<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe final de la Mesa de diversidad, interculturalidad e inclusi\u00f3n. Red de investigaci\u00f3n de Universidades del Estado de Chile<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Gonz\u00e1lez Estay, Celia, Duarte Hidalgo, Cory, Contreras G\u00e1tica, Yasna, C\u00f3rdoba Calqu\u00edn, Claudia, L\u00f3pez Fern\u00e1ndez, Lorena, Correa Silva, Pilar, Mar\u00eda Soledad Burrone Colombino, C\u00e1rdenas Catro, Manuel, Riveros Ferrada, Carolina, Estef\u00f3 Aguero, Silvana, Eterovic D\u00edaz, Claudia, Palma Candia, Oskarina<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/www.uestatales.cl\/cue\/sites\/default\/files\/Clima%20de%20Diversidad%20e%20Inclusi%C3%B3n%20en%20las%20universidades%20estatales_0.pdf<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Clima de diversidad e inclusi\u00f3n en Universidades Estatales, Barreras y Facilitadores<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe final de la Mesa de diversidad, interculturalidad e inclusi\u00f3n. Red de investigaci\u00f3n de Universidades del Estado de Chile<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Gonz\u00e1lez Estay, Celia, Duarte Hidalgo, Cory, Contreras G\u00e1tica, Yasna, C\u00f3rdoba Calqu\u00edn, Claudia, L\u00f3pez Fern\u00e1ndez, Lorena, Correa Silva, Pilar, Mar\u00eda Soledad Burrone Colombino, C\u00e1rdenas Catro, Manuel, Riveros Ferrada, Carolina, Estef\u00f3 Aguero, Silvana, Eterovic D\u00edaz, Claudia, Palma Candia, Oskarina<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Sistematizaci\u00f3n del Taller Programa Estrat\u00e9gico de Investigaci\u00f3n y Desarrollo (PEID): Salud Mental<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe sobre Investigaci\u00f3n y Desarrollo en Salud Mental. Argentina, 2009<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe de sistematizaci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Mar\u00eda Soledad Burrone Colombino, Mar\u00eda Cristina Chardon, Anna Candreva, Norman Pautaso, Mario Kelman<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Sistematizaci\u00f3n del Taller Programa Estrat\u00e9gico de Investigaci\u00f3n y Desarrollo (PEID): Salud Mental<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe sobre Investigaci\u00f3n y Desarrollo en Salud Mental. Argentina, 2009<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe de sistematizaci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Mar\u00eda Soledad Burrone Colombino, Mar\u00eda Cristina Chardon, Anna Candreva, Norman Pautaso, Mario Kelman<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Serie Geolog\u00eda B\u00e1sica; Servicio Nacional de Geolog\u00eda y Miner\u00eda<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Geolog\u00eda de la Isla Robinson Crusoe, Regi\u00f3n de Valpara\u00edso<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">https:\/\/plannacionalgeologia.sernageomin.cl\/project\/geologia-robinson-crusoe\/<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Carta Geol\u00f3gica de Chile<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Luis E. Lara, Javiera Reyes, P. Sep\u00falveda, Gabriel Orozco, Mireia Pi\u00f1a, Laura Becerril Carretero<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Serie Geolog\u00eda B\u00e1sica; Servicio Nacional de Geolog\u00eda y Miner\u00eda<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Geolog\u00eda de la Isla Robinson Crusoe, Regi\u00f3n de Valpara\u00edso<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">https:\/\/plannacionalgeologia.sernageomin.cl\/project\/geologia-robinson-crusoe\/<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Carta Geol\u00f3gica de Chile<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Luis E. Lara, Javiera Reyes, P. Sep\u00falveda, Gabriel Orozco, Mireia Pi\u00f1a, Laura Becerril Carretero<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> The Conversation (versi\u00f3n Espa\u00f1a)<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">El Hierro revela nuevos secretos sobre c\u00f3mo funcionan los volcanes<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">https:\/\/theconversation.com\/el-hierro-revela-nuevos-secretos-sobre-como-funcionan-los-volcanes-166447<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Art\u00edculo de divulgaci\u00f3n cient\u00edfica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Teresa Ubide, Carlos Gal\u00e9, Laura Becerril Carretero, Patricia Larrea<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> The Conversation (versi\u00f3n Espa\u00f1a)<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">El Hierro revela nuevos secretos sobre c\u00f3mo funcionan los volcanes<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">https:\/\/theconversation.com\/el-hierro-revela-nuevos-secretos-sobre-como-funcionan-los-volcanes-166447<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Art\u00edculo de divulgaci\u00f3n cient\u00edfica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Teresa Ubide, Carlos Gal\u00e9, Laura Becerril Carretero, Patricia Larrea<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> The Conversation (versi\u00f3n Espa\u00f1a)<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Estas son las \u0091geoclaves\u0092 de lo que est\u00e1 pasando en La Palma<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">https:\/\/theconversation.com\/estas-son-las-geoclaves-de-lo-que-esta-pasando-en-la-palma-168257<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Art\u00edculo de divulgaci\u00f3n cient\u00edfica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Laura Becerril Carretero, Teresa Ubide, Carlos Gal\u00e9, Patricia Larrea<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> The Conversation (versi\u00f3n Espa\u00f1a)<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Estas son las \u0091geoclaves\u0092 de lo que est\u00e1 pasando en La Palma<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">https:\/\/theconversation.com\/estas-son-las-geoclaves-de-lo-que-esta-pasando-en-la-palma-168257<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Art\u00edculo de divulgaci\u00f3n cient\u00edfica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Laura Becerril Carretero, Teresa Ubide, Carlos Gal\u00e9, Patricia Larrea<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> The Conversation (versi\u00f3n Espa\u00f1a)<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">\u00bfC\u00f3mo evolucionar\u00e1 el nuevo volc\u00e1n de La Palma?<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">https:\/\/theconversation.com\/como-evolucionara-el-nuevo-volcan-de-la-palma-168389<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Art\u00edculo de divulgaci\u00f3n cient\u00edfica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Teresa Ubide, Laura Becerril Carretero, Patricia Larrea, Carlos Gal\u00e9<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> The Conversation (versi\u00f3n Espa\u00f1a)<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">\u00bfC\u00f3mo evolucionar\u00e1 el nuevo volc\u00e1n de La Palma?<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">https:\/\/theconversation.com\/como-evolucionara-el-nuevo-volcan-de-la-palma-168389<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Art\u00edculo de divulgaci\u00f3n cient\u00edfica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Teresa Ubide, Laura Becerril Carretero, Patricia Larrea, Carlos Gal\u00e9<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Subdirecci\u00f3n Nacional de Geolog\u00eda. Programa de Riesgo Volc\u00e1nico. Sernageomin<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Mapa de peligros del campo volc\u00e1nico Carr\u00e1n &#8211; Los Venados, Regi\u00f3n de Los Lagos<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Mapa de peligros del campo volc\u00e1nico Carr\u00e1n - Los Venados, Regi\u00f3n de Los Lagos. Escala 1:50.000.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Mapa de peligros volc\u00e1nicos<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Lizette J. Bertin, Hugo Moreno, Laura Becerril Carretero<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Subdirecci\u00f3n Nacional de Geolog\u00eda. Programa de Riesgo Volc\u00e1nico. Sernageomin<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Mapa de peligros del campo volc\u00e1nico Carr\u00e1n &#8211; Los Venados, Regi\u00f3n de Los Lagos<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Mapa de peligros del campo volc\u00e1nico Carr\u00e1n - Los Venados, Regi\u00f3n de Los Lagos. Escala 1:50.000.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Mapa de peligros volc\u00e1nicos<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Lizette J. Bertin, Hugo Moreno, Laura Becerril Carretero<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> EOS<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Enhancing Safety in a Volcano&#8217;s Shadow<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">A new project gives civil authorities and scientists a common set of tools for assessing volcanic hazards and managing associated risks.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Art\u00edculo de divulgaci\u00f3n cient\u00edfica DOI: 10.1029\/2016EO054161.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Joan Mart\u00ed, Stefania Bartolini, Laura Becerril Carretero<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> EOS<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Enhancing Safety in a Volcano&#8217;s Shadow<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">A new project gives civil authorities and scientists a common set of tools for assessing volcanic hazards and managing associated risks.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Art\u00edculo de divulgaci\u00f3n cient\u00edfica DOI: 10.1029\/2016EO054161.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Joan Mart\u00ed, Stefania Bartolini, Laura Becerril Carretero<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> CONAMA<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Investigaciones dendrogeomorfol\u00f3gicas aplicadas al estudio de la peligrosidad por avenidas e inundaciones en el parque nacional de la Caldera de Taburiente (La Palma, Islas Canarias)<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Art\u00edculo de divulgaci\u00f3n cient\u00edfica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">D\u00edez-Herrero, A,, G\u00e9nova F\u00faster, M., Mayer Su\u00e1rez, P., Ballesteros C\u00e1novas, J.A., Laura Becerril Carretero, Rubiales Jim\u00e9nez, J.M., Hern\u00e1ndez Ruiz, M., Saz Sanchez, M.A., Bodoque del Pozo, J.M., Ruiz Villanueva, V.<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> CONAMA<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Investigaciones dendrogeomorfol\u00f3gicas aplicadas al estudio de la peligrosidad por avenidas e inundaciones en el parque nacional de la Caldera de Taburiente (La Palma, Islas Canarias)<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Art\u00edculo de divulgaci\u00f3n cient\u00edfica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">D\u00edez-Herrero, A,, G\u00e9nova F\u00faster, M., Mayer Su\u00e1rez, P., Ballesteros C\u00e1novas, J.A., Laura Becerril Carretero, Rubiales Jim\u00e9nez, J.M., Hern\u00e1ndez Ruiz, M., Saz Sanchez, M.A., Bodoque del Pozo, J.M., Ruiz Villanueva, V.<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Fondo de Documentaci\u00f3n del Instituto Geol\u00f3gico y Minero de Espa\u00f1a, Madrid<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Investigaciones dendrogeomorfol\u00f3gicas aplicadas a la gesti\u00f3n de los riesgos e impactos en la Red de Parques Nacionales (IDEA-GesPPNN)<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">27 p\u00e1ginas + anexo documental (168 pp.)<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe T\u00e9cnico<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">D\u00edez-Herrero, A,, Baeza Chico, E., Ballesteros C\u00e1novas, J.A., Laura Becerril Carretero<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Fondo de Documentaci\u00f3n del Instituto Geol\u00f3gico y Minero de Espa\u00f1a, Madrid<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Investigaciones dendrogeomorfol\u00f3gicas aplicadas a la gesti\u00f3n de los riesgos e impactos en la Red de Parques Nacionales (IDEA-GesPPNN)<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">27 p\u00e1ginas + anexo documental (168 pp.)<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe T\u00e9cnico<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">D\u00edez-Herrero, A,, Baeza Chico, E., Ballesteros C\u00e1novas, J.A., Laura Becerril Carretero<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Fondo de Documentaci\u00f3n del Instituto Geol\u00f3gico y Minero de Espa\u00f1a, Madrid<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Convenio espec\u00edfico de colaboraci\u00f3n entre el Consejo Insular de Aguas de El Hierro y el Instituto Geol\u00f3gico y Minero de Espa\u00f1a para la realizaci\u00f3n de proyectos y trabajos de investigaci\u00f3n en materia de peligrosidad geol\u00f3gica<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Convenio espec\u00edfico de colaboraci\u00f3n entre el Consejo Insular de Aguas de El Hierro y el Instituto Geol\u00f3gico y Minero de Espa\u00f1a para la realizaci\u00f3n de proyectos y trabajos de investigaci\u00f3n en materia de peligrosidad geol\u00f3gica. 10 Tomos.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe T\u00e9cnico<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">La\u00edn, L., Galindo, I., Rodr\u00edguez, C., Sarro, R., D\u00edez-Herrero, A., Hern\u00e1ndez, M., Laura Becerril Carretero, Morales, J.M., Neuman, J.<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Fondo de Documentaci\u00f3n del Instituto Geol\u00f3gico y Minero de Espa\u00f1a, Madrid<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Convenio espec\u00edfico de colaboraci\u00f3n entre el Consejo Insular de Aguas de El Hierro y el Instituto Geol\u00f3gico y Minero de Espa\u00f1a para la realizaci\u00f3n de proyectos y trabajos de investigaci\u00f3n en materia de peligrosidad geol\u00f3gica<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Convenio espec\u00edfico de colaboraci\u00f3n entre el Consejo Insular de Aguas de El Hierro y el Instituto Geol\u00f3gico y Minero de Espa\u00f1a para la realizaci\u00f3n de proyectos y trabajos de investigaci\u00f3n en materia de peligrosidad geol\u00f3gica. 10 Tomos.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe T\u00e9cnico<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">La\u00edn, L., Galindo, I., Rodr\u00edguez, C., Sarro, R., D\u00edez-Herrero, A., Hern\u00e1ndez, M., Laura Becerril Carretero, Morales, J.M., Neuman, J.<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> XIV Reuni\u00f3n Nacional de Cuaternario<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Aplicaci\u00f3n de t\u00e9cnicas morfom\u00e9tricas para analizar la actividad tect\u00f3nica, volc\u00e1nica y de deslizamientos en la regi\u00f3n central de Costa Rica<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">\u0095\tGalve, J.P., P\u00e9rez-Pe\u00f1a, J.V., Alvarado, G., Aza\u00f1\u00f3n, J.M.; Mora, M., Giaconia, F., Booth-Rea, G., Becerril, L. (2015). Aplicaci\u00f3n de t\u00e9cnicas morfom\u00e9tricas para analizar la actividad tect\u00f3nica, volc\u00e1nica y de deslizamientos en la regi\u00f3n central de Costa Rica. En: Una visi\u00f3n global del Cuaternario. El hombre como condicionante de procesos geol\u00f3gicos (J. P. Galve, J. M. Aza\u00f1\u00f3n, J. V. P\u00e9rez Pe\u00f1a y P. Ruano, Eds.). pp. 158 - 161. Andaluc\u00eda (Espa\u00f1a): XIV Reuni\u00f3n Nacional de Cuaternario. ISBN 978-84-606-9417-5; Legal deposit: GR-876-2015.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Actas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Galve, J.P., P\u00e9rez-Pe\u00f1a, J.V., Alvarado, G., Aza\u00f1\u00f3n, J.M., Mora, M., Giaconia, F., Booth-Rea, G., Laura Becerril Carretero<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> XIV Reuni\u00f3n Nacional de Cuaternario<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Aplicaci\u00f3n de t\u00e9cnicas morfom\u00e9tricas para analizar la actividad tect\u00f3nica, volc\u00e1nica y de deslizamientos en la regi\u00f3n central de Costa Rica<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">\u0095\tGalve, J.P., P\u00e9rez-Pe\u00f1a, J.V., Alvarado, G., Aza\u00f1\u00f3n, J.M.; Mora, M., Giaconia, F., Booth-Rea, G., Becerril, L. (2015). Aplicaci\u00f3n de t\u00e9cnicas morfom\u00e9tricas para analizar la actividad tect\u00f3nica, volc\u00e1nica y de deslizamientos en la regi\u00f3n central de Costa Rica. En: Una visi\u00f3n global del Cuaternario. El hombre como condicionante de procesos geol\u00f3gicos (J. P. Galve, J. M. Aza\u00f1\u00f3n, J. V. P\u00e9rez Pe\u00f1a y P. Ruano, Eds.). pp. 158 - 161. Andaluc\u00eda (Espa\u00f1a): XIV Reuni\u00f3n Nacional de Cuaternario. ISBN 978-84-606-9417-5; Legal deposit: GR-876-2015.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Actas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Galve, J.P., P\u00e9rez-Pe\u00f1a, J.V., Alvarado, G., Aza\u00f1\u00f3n, J.M., Mora, M., Giaconia, F., Booth-Rea, G., Laura Becerril Carretero<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> XIV Reuni\u00f3n Nacional de Cuaternario<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Estimating vent opening probability on El Hierro Island (Canary Islands) using new geochronological data.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Becerril, L., Ubide, T., Gal\u00e9, C., Galindo, I., Morales; J.M., Lago, M., Mart\u00ed, J., Galve, J.P. (2015). Estimating vent opening probability on El Hierro Island (Canary Islands) using new geochronological data. En: Una visi\u00f3n global del Cuaternario. El hombre como condicionante de procesos geol\u00f3gicos (J. P. Galve, J. M. Aza\u00f1\u00f3n, J. V. P\u00e9rez Pe\u00f1a y P. Ruano, Eds.). pp. 150 - 154. Andaluc\u00eda (Espa\u00f1a): XIV Reuni\u00f3n Nacional de Cuaternario. ISBN 978-84-606-9417-5; Legal deposit: GR-876-2015.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Actas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Laura Becerril Carretero, Teresa Ubide, Carlos Gal\u00e9, In\u00e9s Galindo, Jose Mar\u00eda Morales, Marceliano Lago, Joan Mart\u00ed, Jorge Pedro Galve<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> XIV Reuni\u00f3n Nacional de Cuaternario<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Estimating vent opening probability on El Hierro Island (Canary Islands) using new geochronological data.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Becerril, L., Ubide, T., Gal\u00e9, C., Galindo, I., Morales; J.M., Lago, M., Mart\u00ed, J., Galve, J.P. (2015). Estimating vent opening probability on El Hierro Island (Canary Islands) using new geochronological data. En: Una visi\u00f3n global del Cuaternario. El hombre como condicionante de procesos geol\u00f3gicos (J. P. Galve, J. M. Aza\u00f1\u00f3n, J. V. P\u00e9rez Pe\u00f1a y P. Ruano, Eds.). pp. 150 - 154. Andaluc\u00eda (Espa\u00f1a): XIV Reuni\u00f3n Nacional de Cuaternario. ISBN 978-84-606-9417-5; Legal deposit: GR-876-2015.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Actas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Laura Becerril Carretero, Teresa Ubide, Carlos Gal\u00e9, In\u00e9s Galindo, Jose Mar\u00eda Morales, Marceliano Lago, Joan Mart\u00ed, Jorge Pedro Galve<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> XIV Reuni\u00f3n Nacional de Cuaternario<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Long-Term Hazard assessment on Quaternary monogenetic volcanic fields using E-Tools<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Becerril, L., Bartolini, S., Mart\u00ed, J., Geyer, A. (2015). Long-Term Hazard assessment on Quaternary monogenetic volcanic fields using E-Tools. En: Una visi\u00f3n global del Cuaternario. El hombre como condicionante de procesos geol\u00f3gicos (J. P. Galve, J. M. Aza\u00f1\u00f3n, J. V. P\u00e9rez Pe\u00f1a y P. Ruano, Eds.). pp. 155 - 157. Andaluc\u00eda (Espa\u00f1a): XIV Reuni\u00f3n Nacional de Cuaternario. ISBN 978-84-606-9417-5; Legal deposit: GR-876-2015.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Actas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Laura Becerril Carretero, Bartolini, S., Mart\u00ed, J., Geyer, A<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> XIV Reuni\u00f3n Nacional de Cuaternario<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Long-Term Hazard assessment on Quaternary monogenetic volcanic fields using E-Tools<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Becerril, L., Bartolini, S., Mart\u00ed, J., Geyer, A. (2015). Long-Term Hazard assessment on Quaternary monogenetic volcanic fields using E-Tools. En: Una visi\u00f3n global del Cuaternario. El hombre como condicionante de procesos geol\u00f3gicos (J. P. Galve, J. M. Aza\u00f1\u00f3n, J. V. P\u00e9rez Pe\u00f1a y P. Ruano, Eds.). pp. 155 - 157. Andaluc\u00eda (Espa\u00f1a): XIV Reuni\u00f3n Nacional de Cuaternario. ISBN 978-84-606-9417-5; Legal deposit: GR-876-2015.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Actas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Laura Becerril Carretero, Bartolini, S., Mart\u00ed, J., Geyer, A<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> XII Reuni\u00f3n Nacional de Geomorfolog\u00eda, Santander, Espa\u00f1a<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Investigaciones dendrogeomorfol\u00f3gicas aplicadas al estudio de la peligrosidad por avenidas e inundaciones en el parque nacional de la Caldera de Taburiente (La Palma, Islas Canarias).<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00edez-Herrero, A.*, G\u00e9nova, M., Mayer, P., Ballesteros, J.A., Becerril, L., Rubiales, J.M., Guti\u00e9rrez-P\u00e9rez, I., Hern\u00e1ndez, M., Saz, M.A., Bodoque, J.M., Ru\u00edz-Villanueva, V. (2012). Investigaciones dendrogeomorfol\u00f3gicas aplicadas al estudio de la peligrosidad por avenidas e inundaciones en el parque nacional de la Caldera de Taburiente (La Palma, Islas Canarias). XII Reuni\u00f3n Nacional de Geomorfolog\u00eda, Santander, Espa\u00f1a.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Actas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">D\u00edez-Herrero, A., G\u00e9nova, M., Mayer, P., Ballesteros, J.A., Laura Becerril Carretero, Rubiales, J.M., Guti\u00e9rrez-P\u00e9rez, I., Hern\u00e1ndez, M., Saz, M.A., Bodoque, J.M., Ru\u00edz-Villanueva, V.<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> XII Reuni\u00f3n Nacional de Geomorfolog\u00eda, Santander, Espa\u00f1a<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Investigaciones dendrogeomorfol\u00f3gicas aplicadas al estudio de la peligrosidad por avenidas e inundaciones en el parque nacional de la Caldera de Taburiente (La Palma, Islas Canarias).<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00edez-Herrero, A.*, G\u00e9nova, M., Mayer, P., Ballesteros, J.A., Becerril, L., Rubiales, J.M., Guti\u00e9rrez-P\u00e9rez, I., Hern\u00e1ndez, M., Saz, M.A., Bodoque, J.M., Ru\u00edz-Villanueva, V. (2012). Investigaciones dendrogeomorfol\u00f3gicas aplicadas al estudio de la peligrosidad por avenidas e inundaciones en el parque nacional de la Caldera de Taburiente (La Palma, Islas Canarias). XII Reuni\u00f3n Nacional de Geomorfolog\u00eda, Santander, Espa\u00f1a.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Actas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">D\u00edez-Herrero, A., G\u00e9nova, M., Mayer, P., Ballesteros, J.A., Laura Becerril Carretero, Rubiales, J.M., Guti\u00e9rrez-P\u00e9rez, I., Hern\u00e1ndez, M., Saz, M.A., Bodoque, J.M., Ru\u00edz-Villanueva, V.<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Proceedings of the 17th Pan-American Conference on Soil Mechanics and Geotechnical Engineering (XVII PCSMGE), and 2nd Latin-American Regional Conference of the International Association for Engineering Geology and the Environment (IAEG),<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Shallow-seated landslide susceptibility and hazard assessment in volcanic edifices from an engineering geological approach: Case of study Llaima volcano<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">chrome-extension:\/\/efaidnbmnnnibpcajpcglclefindmkaj\/https:\/\/www.issmge.org\/uploads\/publications\/84\/130\/FV_419_-_MT_4_-_FV.pdf<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Proceedings<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Alejandra Serey Amador, Jorge Eduardo Romero Moyano, B. Salinas, A. Salgado, Ivo Fustos-Toribio, Demian Byron Trigo Cruz, Laura Becerril Carretero, Marisol Lara<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Proceedings of the 17th Pan-American Conference on Soil Mechanics and Geotechnical Engineering (XVII PCSMGE), and 2nd Latin-American Regional Conference of the International Association for Engineering Geology and the Environment (IAEG),<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Shallow-seated landslide susceptibility and hazard assessment in volcanic edifices from an engineering geological approach: Case of study Llaima volcano<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">chrome-extension:\/\/efaidnbmnnnibpcajpcglclefindmkaj\/https:\/\/www.issmge.org\/uploads\/publications\/84\/130\/FV_419_-_MT_4_-_FV.pdf<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Proceedings<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Alejandra Serey Amador, Jorge Eduardo Romero Moyano, B. Salinas, A. Salgado, Ivo Fustos-Toribio, Demian Byron Trigo Cruz, Laura Becerril Carretero, Marisol Lara<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Revista Energ\u00eda y Geociencias ACGGP (Colombia) \u0095 Publicaci\u00f3n No. 38<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Importancia de la evaluaci\u00f3n de la amenaza volc\u00e1nica en el Campo Volc\u00e1nico Monogen\u00e9tico Guamuez-Sibundoy<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">https:\/\/www.acggp.org\/revista\/#flipbook-df_31285\/34\/<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Art\u00edculo de divulgaci\u00f3n Cient\u00edfica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Andrea Stefan\u00eda Ortega Silva, Hugo Muercia, Laura Becerril Carretero, \u00c1lvaro Botero<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Revista Energ\u00eda y Geociencias ACGGP (Colombia) \u0095 Publicaci\u00f3n No. 38<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Importancia de la evaluaci\u00f3n de la amenaza volc\u00e1nica en el Campo Volc\u00e1nico Monogen\u00e9tico Guamuez-Sibundoy<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">https:\/\/www.acggp.org\/revista\/#flipbook-df_31285\/34\/<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Art\u00edculo de divulgaci\u00f3n Cient\u00edfica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Andrea Stefan\u00eda Ortega Silva, Hugo Muercia, Laura Becerril Carretero, \u00c1lvaro Botero<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Validaci\u00f3n del uso de los esteroides como herramienta de trazado del origen de las contaminaciones fecales de las aguas superficiales<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Tesis de doctorado<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Morgane Marie Reine Derrien<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Validaci\u00f3n del uso de los esteroides como herramienta de trazado del origen de las contaminaciones fecales de las aguas superficiales<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Tesis de doctorado<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Morgane Marie Reine Derrien<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">INFORME ESTADO DEL ARTE MIGRACI\u00d3N Y SISTEMA ESCOLAR EN CHILE, ARGENTINA Y ESPA\u00d1A<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">En Chile las corrientes migratorias son un fen\u00f3meno de larga data y por ello se pueden\r\ndistinguir periodos hist\u00f3ricos con diversas caracter\u00edsticas. Teniendo en consideraci\u00f3n la\r\nhistoria reciente de este pa\u00eds, un primer momento relevante de migraci\u00f3n lo constituye la\r\nllegada de personas provenientes de Europa durante el siglo XIX y el siglo XX (Cano & Soffia,\r\n2009). Un segundo momento se da a partir del golpe de Estado de 1973, que produjo un\r\n\u00e9xodo significativo de chilenos que emigran a pa\u00edses europeos y Latinoamericanos en\r\ncalidad de refugiados pol\u00edticos (Bolzman, 1993; Pozo, 2004). Con el retorno a la democracia,\r\ndesde 1990 en adelante Chile comienza paulatinamente a destacarse como modelo de\r\ncrecimiento econ\u00f3mico y de estabilidad pol\u00edtica y social en Latinoam\u00e9rica. Ese contexto\r\npermite la reducci\u00f3n significativa de la pobreza y en t\u00e9rminos generales, la posibilidad de\r\ncontar con mejores expectativas econ\u00f3micas y de bienestar material. Esto significa que\r\nhist\u00f3ricamente Chile est\u00e1 en mejores condiciones que antes; y geogr\u00e1ficamente, el pa\u00eds\r\nposee una situaci\u00f3n comparativamente mejor que otros pa\u00edses de la regi\u00f3n. Y es as\u00ed como\r\nChile se constituye en un destino atractivo para personas de otros pa\u00edses de Am\u00e9rica Latina\r\nque deciden migrar al pa\u00eds para mejorar sus condiciones de vida (Salas, del R\u00edo, Kong & San\r\nMart\u00edn, 2016). Por cierto, existen distintos motivos para que personas de otros pa\u00edses\r\ndecidan venir a Chile. Entre estos se pueden destacar: extranjeros con v\u00ednculos con\r\nciudadanos Chilenos, motivos laborales, razones pol\u00edticas, reunificaci\u00f3n familiar, etc. (Rojas\r\n& Silva; 2016).\r\nDe esta forma, Chile pasa de ser un pa\u00eds emisor de migrantes a constituirse en un destino\r\nde migraci\u00f3n (Castillo, 2016: 5), lo que da cuenta de un nuevo patr\u00f3n migratorio a nivel\r\nnacional (Cano, Soffia & Mart\u00ednez, 2009). Dicha din\u00e1mica ha recibido el nombre de Nueva\r\ninmigraci\u00f3n (Pavez & Lewin, 2014).1 Y este fen\u00f3meno ha sido estudiado por destacados\r\nacad\u00e9micos nacionales. Evidentemente estos autores han contribuido a entender algo que\r\npodr\u00edamos nombrar como una nueva cuesti\u00f3n social. Sin embargo, tal como se\u00f1ala Pavez y\r\nLewin (2014); y tambi\u00e9n Tijoux (2013), el foco generalmente se ha centrado en la poblaci\u00f3n\r\nadulta y no en ni\u00f1os y ni\u00f1as migrantes o hijos e hijas de migrantes. Eso es un problema en\r\ntanto las primeras generaciones de migrantes, cuando ya logran cierto nivel de estabilidad\r\necon\u00f3mica, buscan formas para que sus familias puedan reunirse con ellas en el pa\u00eds de\r\ndestino migratorio. A su vez, esta reunificaci\u00f3n familiar y la formaci\u00f3n de nuevas familias\r\nposibilitan el nacimiento de ni\u00f1os, ni\u00f1as y adolescentes descendientes de migrantes, los\r\ncuales se enfrentan a matrices de inclusi\u00f3n\/exclusi\u00f3n social (Rojas, Amode & V\u00e1squez,\r\n2015) como el sistema escolar.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Ministerio de Educaci\u00f3n, Chile<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">David Eduardo Mart\u00ednez Rojas<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">INFORME ESTADO DEL ARTE MIGRACI\u00d3N Y SISTEMA ESCOLAR EN CHILE, ARGENTINA Y ESPA\u00d1A<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">En Chile las corrientes migratorias son un fen\u00f3meno de larga data y por ello se pueden\r\ndistinguir periodos hist\u00f3ricos con diversas caracter\u00edsticas. Teniendo en consideraci\u00f3n la\r\nhistoria reciente de este pa\u00eds, un primer momento relevante de migraci\u00f3n lo constituye la\r\nllegada de personas provenientes de Europa durante el siglo XIX y el siglo XX (Cano & Soffia,\r\n2009). Un segundo momento se da a partir del golpe de Estado de 1973, que produjo un\r\n\u00e9xodo significativo de chilenos que emigran a pa\u00edses europeos y Latinoamericanos en\r\ncalidad de refugiados pol\u00edticos (Bolzman, 1993; Pozo, 2004). Con el retorno a la democracia,\r\ndesde 1990 en adelante Chile comienza paulatinamente a destacarse como modelo de\r\ncrecimiento econ\u00f3mico y de estabilidad pol\u00edtica y social en Latinoam\u00e9rica. Ese contexto\r\npermite la reducci\u00f3n significativa de la pobreza y en t\u00e9rminos generales, la posibilidad de\r\ncontar con mejores expectativas econ\u00f3micas y de bienestar material. Esto significa que\r\nhist\u00f3ricamente Chile est\u00e1 en mejores condiciones que antes; y geogr\u00e1ficamente, el pa\u00eds\r\nposee una situaci\u00f3n comparativamente mejor que otros pa\u00edses de la regi\u00f3n. Y es as\u00ed como\r\nChile se constituye en un destino atractivo para personas de otros pa\u00edses de Am\u00e9rica Latina\r\nque deciden migrar al pa\u00eds para mejorar sus condiciones de vida (Salas, del R\u00edo, Kong & San\r\nMart\u00edn, 2016). Por cierto, existen distintos motivos para que personas de otros pa\u00edses\r\ndecidan venir a Chile. Entre estos se pueden destacar: extranjeros con v\u00ednculos con\r\nciudadanos Chilenos, motivos laborales, razones pol\u00edticas, reunificaci\u00f3n familiar, etc. (Rojas\r\n& Silva; 2016).\r\nDe esta forma, Chile pasa de ser un pa\u00eds emisor de migrantes a constituirse en un destino\r\nde migraci\u00f3n (Castillo, 2016: 5), lo que da cuenta de un nuevo patr\u00f3n migratorio a nivel\r\nnacional (Cano, Soffia & Mart\u00ednez, 2009). Dicha din\u00e1mica ha recibido el nombre de Nueva\r\ninmigraci\u00f3n (Pavez & Lewin, 2014).1 Y este fen\u00f3meno ha sido estudiado por destacados\r\nacad\u00e9micos nacionales. Evidentemente estos autores han contribuido a entender algo que\r\npodr\u00edamos nombrar como una nueva cuesti\u00f3n social. Sin embargo, tal como se\u00f1ala Pavez y\r\nLewin (2014); y tambi\u00e9n Tijoux (2013), el foco generalmente se ha centrado en la poblaci\u00f3n\r\nadulta y no en ni\u00f1os y ni\u00f1as migrantes o hijos e hijas de migrantes. Eso es un problema en\r\ntanto las primeras generaciones de migrantes, cuando ya logran cierto nivel de estabilidad\r\necon\u00f3mica, buscan formas para que sus familias puedan reunirse con ellas en el pa\u00eds de\r\ndestino migratorio. A su vez, esta reunificaci\u00f3n familiar y la formaci\u00f3n de nuevas familias\r\nposibilitan el nacimiento de ni\u00f1os, ni\u00f1as y adolescentes descendientes de migrantes, los\r\ncuales se enfrentan a matrices de inclusi\u00f3n\/exclusi\u00f3n social (Rojas, Amode & V\u00e1squez,\r\n2015) como el sistema escolar.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Ministerio de Educaci\u00f3n, Chile<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">David Eduardo Mart\u00ednez Rojas<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Escuelas socioecon\u00f3micamente diversas en Santiago: Entre la  celebraci\u00f3n de las diferencias y el asimilacionismo<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">https:\/\/educacion.uahurtado.cl\/wpsite\/wp-content\/uploads\/2021\/01\/WP_6_Manuela_Mendoza.pdf<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Manuela Ji Mendoza Horvitz<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Escuelas socioecon\u00f3micamente diversas en Santiago: Entre la  celebraci\u00f3n de las diferencias y el asimilacionismo<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">https:\/\/educacion.uahurtado.cl\/wpsite\/wp-content\/uploads\/2021\/01\/WP_6_Manuela_Mendoza.pdf<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Manuela Ji Mendoza Horvitz<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Minnesota Environment and Natural Resources Trust Fund<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Banking Groundwater \u0096 A study examining aquifer storage and recovery for groundwater sustainability in Minnesota<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Carrie E. Jennings, John Bilotta, William Arnold, Peter K. Kang, Seonkyoo Yoon, Raghwendra N. Shandilya, Etienne Samuel Bresciani, Seunghak Lee, Joshua Kirk, Lucia Levers, Brian Bohman, Eileen Kirby, Anthony C. Runkel, Galen Xiang, Phillip Gassman, Adriana Valcu-Lisman<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Department of Environment, Water and Natural Resources, Government of South Australia<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Further development of the Goyder Institute Adelaide Plains regional groundwater model (AP2017)<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Etienne Samuel Bresciani, Okke Batelaan<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Minnesota Environment and Natural Resources Trust Fund<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Banking Groundwater \u0096 A study examining aquifer storage and recovery for groundwater sustainability in Minnesota<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Carrie E. Jennings, John Bilotta, William Arnold, Peter K. Kang, Seonkyoo Yoon, Raghwendra N. Shandilya, Etienne Samuel Bresciani, Seunghak Lee, Joshua Kirk, Lucia Levers, Brian Bohman, Eileen Kirby, Anthony C. Runkel, Galen Xiang, Phillip Gassman, Adriana Valcu-Lisman<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Goyder Institute for Water Research<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Assessment of Adelaide Plains Groundwater Resources: Appendices Part II \u0096 Regional Groundwater Modelling<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Etienne Samuel Bresciani, Okke Batelaan, Eddie W. Banks, S. R. Barnett, Jordi Batlle-Aguilar, Peter G. Cook, Adrian Costar, Roger H. Cranswick, John Doherty, Graham Green, John Kozuskanich, Daniel Partington, Maria Pool, V.E.A. Post, Craig T. Simmons, Brian D. Smerdon, S. D. Smith, Chris Turnadge, S. Villeneuve, A. D. Werner, N. White, Y. Xie<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Department of Environment, Water and Natural Resources, Government of South Australia<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Further development of the Goyder Institute Adelaide Plains regional groundwater model (AP2017)<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Etienne Samuel Bresciani, Okke Batelaan<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Goyder Institute for Water Research<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Assessment of Adelaide Plains Groundwater Resources: Appendices Part II \u0096 Regional Groundwater Modelling<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Etienne Samuel Bresciani, Okke Batelaan, Eddie W. Banks, S. R. Barnett, Jordi Batlle-Aguilar, Peter G. Cook, Adrian Costar, Roger H. Cranswick, John Doherty, Graham Green, John Kozuskanich, Daniel Partington, Maria Pool, V.E.A. Post, Craig T. Simmons, Brian D. Smerdon, S. D. Smith, Chris Turnadge, S. Villeneuve, A. D. Werner, N. White, Y. Xie<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Goyder Institute for Water Research<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Assessment of Adelaide Plains Groundwater Resources: Appendices Part I \u0096 Field and Desktop Investigations<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Etienne Samuel Bresciani, Okke Batelaan, Eddie W. Banks, S. R. Barnett, Jordi Batlle-Aguilar, Peter G. Cook, Adrian Costar, Roger H. Cranswick, John Doherty, Graham Green, John Kozuskanich, Daniel Partington, Maria Pool, V.E.A. Post, Craig T. Simmons, Brian D. Smerdon, S. D. Smith, Chris Turnadge, S. Villeneuve, A. D. Werner, N. White, Y. Xie<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Goyder Institute for Water Research<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Assessment of Adelaide Plains Groundwater Resources: Appendices Part I \u0096 Field and Desktop Investigations<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Etienne Samuel Bresciani, Okke Batelaan, Eddie W. Banks, S. R. Barnett, Jordi Batlle-Aguilar, Peter G. Cook, Adrian Costar, Roger H. Cranswick, John Doherty, Graham Green, John Kozuskanich, Daniel Partington, Maria Pool, V.E.A. Post, Craig T. Simmons, Brian D. Smerdon, S. D. Smith, Chris Turnadge, S. Villeneuve, A. D. Werner, N. White, Y. Xie<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Goyder Institute for Water Research<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Assessment of Adelaide Plains Groundwater Resources: Summary Report<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Etienne Samuel Bresciani, Okke Batelaan, Eddie W. Banks, S. R. Barnett, Jordi Batlle-Aguilar, Peter G. Cook, Adrian Costar, Roger H. Cranswick, John Doherty, Graham Green, John Kozuskanich, Daniel Partington, Maria Pool, V.E.A. Post, Craig T. Simmons, Brian D. Smerdon, S. D. Smith, Chris Turnadge, S. Villeneuve, A. D. Werner, N. White, Y. Xie<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Goyder Institute for Water Research<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Assessment of Adelaide Plains Groundwater Resources: Summary Report<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Etienne Samuel Bresciani, Okke Batelaan, Eddie W. Banks, S. R. Barnett, Jordi Batlle-Aguilar, Peter G. Cook, Adrian Costar, Roger H. Cranswick, John Doherty, Graham Green, John Kozuskanich, Daniel Partington, Maria Pool, V.E.A. Post, Craig T. Simmons, Brian D. Smerdon, S. D. Smith, Chris Turnadge, S. Villeneuve, A. D. Werner, N. White, Y. Xie<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/flacsolab.cl\/wp-content\/uploads\/2021\/12\/Informe-DDHH-comision.pdf<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Informe verdad hist\u00f3rica, reparaci\u00f3n integral y garant\u00edas de no repetici\u00f3n<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">An\u00e1lisis de las audiencias de organizaciones de personas con discapacidad presentas en la convenci\u00f3n constitucional<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Capitulo de Personas en situaci\u00f3n de discapacidad<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Juan Andr\u00e9s Pino Mor\u00e1n<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/flacsolab.cl\/wp-content\/uploads\/2021\/12\/Informe-DDHH-comision.pdf<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Informe verdad hist\u00f3rica, reparaci\u00f3n integral y garant\u00edas de no repetici\u00f3n<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">An\u00e1lisis de las audiencias de organizaciones de personas con discapacidad presentas en la convenci\u00f3n constitucional<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Capitulo de Personas en situaci\u00f3n de discapacidad<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Juan Andr\u00e9s Pino Mor\u00e1n<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Evaluaci\u00f3n contextualizada e hist\u00f3rica de los Liceos Bicentenario de Excelencia<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Reporte para el ministerio de educaci\u00f3n sobre los liceos bicentenarios.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Alejandro Carrasco, Cristobal Villalobos, Gabriel Jes\u00fas Gutti\u00e9rez Cofre, Ngaire Noelle Honey, Gisela Dibona, Sebasti\u00e1n Pereira, Francisca Rostagno, Sebasti\u00e1n Buzeta, Ernesto Trevi\u00f1o<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Evaluar para Reactivar el Aprendizaje: Explorando Valoraci\u00f3n y Expectativas de Docentes y Directivos de Ense\u00f1anza Media sobre Evaluaci\u00f3n<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Un informe final para el proyecto Fonide 14. Tiene la explicaci\u00f3n de los m\u00e9todos de investigaci\u00f3n y los resultados de la investigaci\u00f3n usando m\u00e9todos mixtos. Hicimos 4 versiones, cada uno con comentarios del representantes del ministerio de educaci\u00f3n.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe Final Fonide<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Ngaire Noelle Honey, \u00c1lvaro Felipe Gonz\u00e1lez Torres, Paulina Contreras Leiva, Mar\u00eda Paz Fa\u00fandez Bast\u00edas, Gabriel Guti\u00e9rrez Cofr\u00e9<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Evaluaci\u00f3n contextualizada e hist\u00f3rica de los Liceos Bicentenario de Excelencia<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Reporte para el ministerio de educaci\u00f3n sobre los liceos bicentenarios.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Alejandro Carrasco, Cristobal Villalobos, Gabriel Jes\u00fas Gutti\u00e9rez Cofre, Ngaire Noelle Honey, Gisela Dibona, Sebasti\u00e1n Pereira, Francisca Rostagno, Sebasti\u00e1n Buzeta, Ernesto Trevi\u00f1o<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Evaluar para Reactivar el Aprendizaje: Explorando Valoraci\u00f3n y Expectativas de Docentes y Directivos de Ense\u00f1anza Media sobre Evaluaci\u00f3n<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Un informe final para el proyecto Fonide 14. Tiene la explicaci\u00f3n de los m\u00e9todos de investigaci\u00f3n y los resultados de la investigaci\u00f3n usando m\u00e9todos mixtos. Hicimos 4 versiones, cada uno con comentarios del representantes del ministerio de educaci\u00f3n.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe Final Fonide<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Ngaire Noelle Honey, \u00c1lvaro Felipe Gonz\u00e1lez Torres, Paulina Contreras Leiva, Mar\u00eda Paz Fa\u00fandez Bast\u00edas, Gabriel Guti\u00e9rrez Cofr\u00e9<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Vigilantismos y territorios latinoamericanos. Pensando en las tensiones entre Estados, escalas y categor\u00edas<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Bolet\u00edn CLACSO Violencias colectivas en Latinoam\u00e9rica. Una mirada cr\u00edtica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Loreto Francisca Quiroz Rojas, Evangelina Caravaca<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Vigilantismos y territorios latinoamericanos. Pensando en las tensiones entre Estados, escalas y categor\u00edas<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Bolet\u00edn CLACSO Violencias colectivas en Latinoam\u00e9rica. Una mirada cr\u00edtica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Loreto Francisca Quiroz Rojas, Evangelina Caravaca<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> CLACSO<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Covid-19 en Chile. Formas de gesti\u00f3n de la crisis, deslegitimaci\u00f3n de las autoridades y punitivismo social en tiempos de pandemia<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Bolet\u00edn CLACSO Violencias colectivas en Latinoam\u00e9rica. Una mirada cr\u00edtica. N\u00b0 1<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Loreto Francisca Quiroz Rojas<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> CLACSO<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Covid-19 en Chile. Formas de gesti\u00f3n de la crisis, deslegitimaci\u00f3n de las autoridades y punitivismo social en tiempos de pandemia<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Bolet\u00edn CLACSO Violencias colectivas en Latinoam\u00e9rica. Una mirada cr\u00edtica. N\u00b0 1<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Loreto Francisca Quiroz Rojas<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Universidad de Sancti Sp\u00edritus  (UNISS)<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">El suelo en el siglo XXI<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Plegables para su divulgaci\u00f3n entre productores y acad\u00e9micos en conmemoraci\u00f3n al a\u00f1o internacional de los suelo.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Plegable<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Dilier Olivera Viciedo<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Universidad de Sancti Sp\u00edritus  (UNISS)<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">El suelo en el siglo XXI<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Plegables para su divulgaci\u00f3n entre productores y acad\u00e9micos en conmemoraci\u00f3n al a\u00f1o internacional de los suelo.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Plegable<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Dilier Olivera Viciedo<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Universidad de Sancti Sp\u00edritus  (UNISS)<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Erosi\u00f3n y salinidad del suelo<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Plegables para su divulgaci\u00f3n entre productores y acad\u00e9micos en conmemoraci\u00f3n al a\u00f1o internacional de los suelo.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Plegable<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Dilier Olivera Viciedo<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Universidad de Sancti Sp\u00edritus  (UNISS)<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Erosi\u00f3n y salinidad del suelo<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Plegables para su divulgaci\u00f3n entre productores y acad\u00e9micos en conmemoraci\u00f3n al a\u00f1o internacional de los suelo.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Plegable<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Dilier Olivera Viciedo<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Universidad de Sancti Sp\u00edritus  (UNISS)<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Suelo y Nutrici\u00f3n<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Plegables para su divulgaci\u00f3n entre productores y acad\u00e9micos en conmemoraci\u00f3n al a\u00f1o internacional de los suelo.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Plegable<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Dilier Olivera Viciedo<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Universidad de Sancti Sp\u00edritus  (UNISS)<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Suelo y Nutrici\u00f3n<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Plegables para su divulgaci\u00f3n entre productores y acad\u00e9micos en conmemoraci\u00f3n al a\u00f1o internacional de los suelo.<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Plegable<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Dilier Olivera Viciedo<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Proceedings of the 17th Pan-American Conference on Soil Mechanics and Geotechnical Engineering (XVII PCSMGE), and 2nd Latin-American Regional Conference of the International Association for Engineering Geology and the Environment (IAEG),<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Shallow-seated landslide susceptibility and hazard assessment in volcanic edifices from an engineering geological approach: Case of study Llaima volcano<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">chrome-extension:\/\/efaidnbmnnnibpcajpcglclefindmkaj\/https:\/\/www.issmge.org\/uploads\/publications\/84\/130\/FV_419_-_MT_4_-_FV.pdf<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Proceedings<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Alejandra Serey Amador, Jorge Eduardo Romero Moyano, B. Salinas, A. Salgado, Ivo Fustos-Toribio, Demian Byron Trigo Cruz, Laura Becerril Carretero, Marisol Lara<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Proceedings of the 17th Pan-American Conference on Soil Mechanics and Geotechnical Engineering (XVII PCSMGE), and 2nd Latin-American Regional Conference of the International Association for Engineering Geology and the Environment (IAEG),<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Shallow-seated landslide susceptibility and hazard assessment in volcanic edifices from an engineering geological approach: Case of study Llaima volcano<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">chrome-extension:\/\/efaidnbmnnnibpcajpcglclefindmkaj\/https:\/\/www.issmge.org\/uploads\/publications\/84\/130\/FV_419_-_MT_4_-_FV.pdf<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Proceedings<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Alejandra Serey Amador, Jorge Eduardo Romero Moyano, B. Salinas, A. Salgado, Ivo Fustos-Toribio, Demian Byron Trigo Cruz, Laura Becerril Carretero, Marisol Lara<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Policy Brief: planificaci\u00f3n territorial de la oferta escolar p\u00fablica: avanzando en sustentabilidad y equidad, Universidad de Chile<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jorge Amaya, Catalina Cecilia Canals Cifuentes, Alejandra Mizala, Patricio Rodr\u00edguez, Paula Uribe, Juan Pablo Valenzuela C\u00e9spedes<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Policy Brief: planificaci\u00f3n territorial de la oferta escolar p\u00fablica: avanzando en sustentabilidad y equidad, Universidad de Chile<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jorge Amaya, Catalina Cecilia Canals Cifuentes, Alejandra Mizala, Patricio Rodr\u00edguez, Paula Uribe, Juan Pablo Valenzuela C\u00e9spedes<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/brain-lab.netlify.app\/post\/studyingandlivinginbristol\/<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Pursuing doctoral studies in the UK<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Post about my personal experience pursuing my doctoral studies in the UK...<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Post<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Carlos Eduardo Mu\u00f1oz Neira<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/brain-lab.netlify.app\/post\/studyingandlivinginbristol\/<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Pursuing doctoral studies in the UK<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Post about my personal experience pursuing my doctoral studies in the UK...<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Post<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Carlos Eduardo Mu\u00f1oz Neira<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/zenodo.org\/records\/15526751<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">IPBES Transformative Change Assessment Data Management Report on the case study database with transformative potential and pitfalls<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Gabriela Andrea Guevara Cue<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/doi.org\/10.17605\/OSF.IO\/RC94T<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Transformation Action Database \/ Base de datos acciones de transformaci\u00f3n.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Transformation Action Database \/ Base de datos acciones de transformaci\u00f3n. https:\/\/doi.org\/10.17605\/OSF.IO\/RC94T<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Paulina A-, Gabriela Andrea Guevara Cue, Francisca Mu\u00f1oz-Brav<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/zenodo.org\/records\/15526751<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">IPBES Transformative Change Assessment Data Management Report on the case study database with transformative potential and pitfalls<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Gabriela Andrea Guevara Cue<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/doi.org\/10.17605\/OSF.IO\/RC94T<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Transformation Action Database \/ Base de datos acciones de transformaci\u00f3n.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Transformation Action Database \/ Base de datos acciones de transformaci\u00f3n. https:\/\/doi.org\/10.17605\/OSF.IO\/RC94T<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Paulina A-, Gabriela Andrea Guevara Cue, Francisca Mu\u00f1oz-Brav<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/mnpt.cl\/2025\/07\/30\/principales-resultados-de-la-investigacion-desarrollada-por-el-centro-de-estudios-en-seguridad-ciudadana-cesc-de-la-universidad-de-chile-en-el-marco-del-proyecto-monitoreo-de-los-medios-herramien\/<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Prevenir la tortura mediante la supervisi\u00f3n de armamento menos letal: l\u00edmites del uso de la fuerza.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe con resultados del Proyecto del Fondo Especial de Prevenci\u00f3n de Tortura de las Naciones Unidas realizado por CESC en conjunto con el Mecanismo Nacional de Prevenci\u00f3n de la Tortura<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Javier Eduardo Vel\u00e1squez Valenzuela, Luis Vergara Cisternas<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> https:\/\/mnpt.cl\/2025\/07\/30\/principales-resultados-de-la-investigacion-desarrollada-por-el-centro-de-estudios-en-seguridad-ciudadana-cesc-de-la-universidad-de-chile-en-el-marco-del-proyecto-monitoreo-de-los-medios-herramien\/<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Prevenir la tortura mediante la supervisi\u00f3n de armamento menos letal: l\u00edmites del uso de la fuerza.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe con resultados del Proyecto del Fondo Especial de Prevenci\u00f3n de Tortura de las Naciones Unidas realizado por CESC en conjunto con el Mecanismo Nacional de Prevenci\u00f3n de la Tortura<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Informe<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Javier Eduardo Vel\u00e1squez Valenzuela, Luis Vergara Cisternas<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Ciper Chile<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Recurso de amparo y justificaci\u00f3n racional de las prisiones preventivas: reflexiones a prop\u00f3sito de la jurisprudencia de la Corte Suprema<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Los autores de esta columna analizan el aumento de la v\u00eda del recurso de amparo para revocar la medida cautelar de la prisi\u00f3n preventiva. Sostienen que \u00abla se\u00f1al que est\u00e1 mandando la Corte es correcta: es necesario mejorar la calidad de la motivaci\u00f3n, ya que explicar en cada caso la raz\u00f3n por la cual la libertad del imputado es, o no, un riesgo para la finalidad del proceso permite racionalizar el uso de la prisi\u00f3n preventiva. Mejora la transparencia del proceso decisional y, por tanto, ayuda a su legitimidad\u00bb.\r\n\r\nhttps:\/\/www.ciperchile.cl\/2025\/06\/22\/recurso-de-amparo-y-justificacion-racional-de-las-prisiones-preventivas-reflexiones-a-proposito-de-la-jurisprudencia-de-la-corte-suprema\/<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Columna<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Mauricio Duce Julio, Javier Eduardo Vel\u00e1squez Valenzuela<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Controversias Penales - Instituto de Ciencias Penales<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Uso de fuerza de Carabineros: Un problema de Derecho P\u00fablico\u0094.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">https:\/\/www.icpenales.cl\/entrada\/uso-de-fuerza-de-carabineros-un-problema-de-derecho-publico<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Columna<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Javier Eduardo Vel\u00e1squez Valenzuela<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Ciper Chile<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Recurso de amparo y justificaci\u00f3n racional de las prisiones preventivas: reflexiones a prop\u00f3sito de la jurisprudencia de la Corte Suprema<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Los autores de esta columna analizan el aumento de la v\u00eda del recurso de amparo para revocar la medida cautelar de la prisi\u00f3n preventiva. Sostienen que \u00abla se\u00f1al que est\u00e1 mandando la Corte es correcta: es necesario mejorar la calidad de la motivaci\u00f3n, ya que explicar en cada caso la raz\u00f3n por la cual la libertad del imputado es, o no, un riesgo para la finalidad del proceso permite racionalizar el uso de la prisi\u00f3n preventiva. Mejora la transparencia del proceso decisional y, por tanto, ayuda a su legitimidad\u00bb.\r\n\r\nhttps:\/\/www.ciperchile.cl\/2025\/06\/22\/recurso-de-amparo-y-justificacion-racional-de-las-prisiones-preventivas-reflexiones-a-proposito-de-la-jurisprudencia-de-la-corte-suprema\/<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Columna<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Mauricio Duce Julio, Javier Eduardo Vel\u00e1squez Valenzuela<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Controversias Penales - Instituto de Ciencias Penales<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Uso de fuerza de Carabineros: Un problema de Derecho P\u00fablico\u0094.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">https:\/\/www.icpenales.cl\/entrada\/uso-de-fuerza-de-carabineros-un-problema-de-derecho-publico<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Columna<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Javier Eduardo Vel\u00e1squez Valenzuela<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Ciper Chile<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">No disparar a la multitud. Prohibiciones internacionales en el uso de la munici\u00f3n antidisturbios que Carabineros no cumple<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Al examinar la normativa internacional relativa al uso de la munici\u00f3n antidisturbios, los autores detectan que los protocolos de Carabineros tienen importantes deficiencias: no advierten sobre la distancia m\u00ednima para disparar; no obligan a apuntar a la parte inferior del cuerpo ni limitan su uso a personas violentas identificadas, sino que se autoriza a disparar a la muchedumbre. Llaman a las autoridades civiles a intervenir y no dejar estos protocolos al arbitrio de la polic\u00eda.\r\n\r\nhttps:\/\/www.ciperchile.cl\/2020\/05\/28\/no-disparar-a-la-multitud-prohibiciones-internacionales-en-el-uso-de-la-municion-anti-disturbio-que-carabineros-no-cumple\/<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Columna<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Catalina Fernandez Carter, Javier Eduardo Vel\u00e1squez Valenzuela<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Ciper Chile<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">No disparar a la multitud. Prohibiciones internacionales en el uso de la munici\u00f3n antidisturbios que Carabineros no cumple<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Al examinar la normativa internacional relativa al uso de la munici\u00f3n antidisturbios, los autores detectan que los protocolos de Carabineros tienen importantes deficiencias: no advierten sobre la distancia m\u00ednima para disparar; no obligan a apuntar a la parte inferior del cuerpo ni limitan su uso a personas violentas identificadas, sino que se autoriza a disparar a la muchedumbre. Llaman a las autoridades civiles a intervenir y no dejar estos protocolos al arbitrio de la polic\u00eda.\r\n\r\nhttps:\/\/www.ciperchile.cl\/2020\/05\/28\/no-disparar-a-la-multitud-prohibiciones-internacionales-en-el-uso-de-la-municion-anti-disturbio-que-carabineros-no-cumple\/<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Columna<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Catalina Fernandez Carter, Javier Eduardo Vel\u00e1squez Valenzuela<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Ciper Chile<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">\u00bfNo letales? El da\u00f1o que ha causado la munici\u00f3n que dispara Carabineros a los manifestantes y por qu\u00e9 debe prohibirse<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Las llaman \u0093no letales\u0094. Pero los autores de esta columna afirman que Carabineros se refiere as\u00ed a las municiones que usa en las protestas s\u00f3lo para intentar legitimarlas. Esta munici\u00f3n, explican, es capaz de matar a determinada distancia y Carabineros no tiene una adecuada regulaci\u00f3n interna sobre su uso pese a que, como lo revel\u00f3 una investigaci\u00f3n de CIPER, la instituci\u00f3n conoce sus riesgos desde al menos el 2012. Peor a\u00fan, al llamarla \u0093no letal\u0094, la instituci\u00f3n hace que sus funcionarios la usen sin tener conciencia de su peligrosidad, afirman.\r\n\r\nhttps:\/\/www.ciperchile.cl\/2020\/05\/27\/no-letales-el-dano-que-ha-causado-la-municion-que-dispara-carabineros-a-los-manifestantes-y-por-que-debe-prohibirse\/<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Columna<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Javier Eduardo Vel\u00e1squez Valenzuela, Catalina Fernandez Carter<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Ciper Chile<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">\u00bfNo letales? El da\u00f1o que ha causado la munici\u00f3n que dispara Carabineros a los manifestantes y por qu\u00e9 debe prohibirse<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Las llaman \u0093no letales\u0094. Pero los autores de esta columna afirman que Carabineros se refiere as\u00ed a las municiones que usa en las protestas s\u00f3lo para intentar legitimarlas. Esta munici\u00f3n, explican, es capaz de matar a determinada distancia y Carabineros no tiene una adecuada regulaci\u00f3n interna sobre su uso pese a que, como lo revel\u00f3 una investigaci\u00f3n de CIPER, la instituci\u00f3n conoce sus riesgos desde al menos el 2012. Peor a\u00fan, al llamarla \u0093no letal\u0094, la instituci\u00f3n hace que sus funcionarios la usen sin tener conciencia de su peligrosidad, afirman.\r\n\r\nhttps:\/\/www.ciperchile.cl\/2020\/05\/27\/no-letales-el-dano-que-ha-causado-la-municion-que-dispara-carabineros-a-los-manifestantes-y-por-que-debe-prohibirse\/<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Columna<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Javier Eduardo Vel\u00e1squez Valenzuela, Catalina Fernandez Carter<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> El Mostrador<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">La privaci\u00f3n del derecho a voto de los reos y los ciudadanos \u0093durmientes<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Esperar que los individuos que han cumplido su condena retornen a la escena social y pol\u00edtica habiendo internalizado y desarrollado un compromiso con el respeto y cumplimiento de la ley, es patentemente absurdo. La situaci\u00f3n carcelaria actual no permite el desarrollo de aquellos compromisos. El castigo que han recibido no es de aquellos que posibiliten el reconocimiento de una autoridad leg\u00edtima o permitan el surgimiento de un di\u00e1logo c\u00edvico que invite a un compromiso normativo. Por el contrario, el tipo de castigo que impone el Estado es uno que perpet\u00faa y reproduce la desigualdad y la exclusi\u00f3n de esta poblaci\u00f3n. \r\n\r\nhttps:\/\/www.elmostrador.cl\/noticias\/opinion\/2017\/11\/09\/la-privacion-del-derecho-a-voto-de-los-reos-y-los-ciudadanos-durmientes\/<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Columna<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Fergus McNeill, Javier Eduardo Vel\u00e1squez Valenzuela<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> El Mostrador<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">La privaci\u00f3n del derecho a voto de los reos y los ciudadanos \u0093durmientes<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Esperar que los individuos que han cumplido su condena retornen a la escena social y pol\u00edtica habiendo internalizado y desarrollado un compromiso con el respeto y cumplimiento de la ley, es patentemente absurdo. La situaci\u00f3n carcelaria actual no permite el desarrollo de aquellos compromisos. El castigo que han recibido no es de aquellos que posibiliten el reconocimiento de una autoridad leg\u00edtima o permitan el surgimiento de un di\u00e1logo c\u00edvico que invite a un compromiso normativo. Por el contrario, el tipo de castigo que impone el Estado es uno que perpet\u00faa y reproduce la desigualdad y la exclusi\u00f3n de esta poblaci\u00f3n. \r\n\r\nhttps:\/\/www.elmostrador.cl\/noticias\/opinion\/2017\/11\/09\/la-privacion-del-derecho-a-voto-de-los-reos-y-los-ciudadanos-durmientes\/<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Columna<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Fergus McNeill, Javier Eduardo Vel\u00e1squez Valenzuela<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Scottich Centre for Crime & Justice Research Blog<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Prisoners, disenfranchisement and sleeping citizenship<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">In this post, Fergus McNeill and Javier Velasquez (University of Glasgow) look further afield, considering current legal challenges surrounding the right to vote for prisoners in Chile, and their implications for civic dialogue and processes of reintegration and desistance from crime.\r\n\r\nhttps:\/\/www.sccjr.ac.uk\/news_item\/prisoners-disenfranchisement-and-sleeping-citizenship\/<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Columna<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Fergus McNeill, Javier Eduardo Vel\u00e1squez Valenzuela<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> Scottich Centre for Crime & Justice Research Blog<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Prisoners, disenfranchisement and sleeping citizenship<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">In this post, Fergus McNeill and Javier Velasquez (University of Glasgow) look further afield, considering current legal challenges surrounding the right to vote for prisoners in Chile, and their implications for civic dialogue and processes of reintegration and desistance from crime.\r\n\r\nhttps:\/\/www.sccjr.ac.uk\/news_item\/prisoners-disenfranchisement-and-sleeping-citizenship\/<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Columna<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Fergus McNeill, Javier Eduardo Vel\u00e1squez Valenzuela<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Financiamiento del desarrollo local: \u00bfen qu\u00e9 compete a la salmonicultura?<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Salmonexpert, 38(6), 54-57<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">\u00c1lvaro Javier Rom\u00e1n Castillo<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Financiamiento del desarrollo local: \u00bfen qu\u00e9 compete a la salmonicultura?<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Salmonexpert, 38(6), 54-57<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">\u00c1lvaro Javier Rom\u00e1n Castillo<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Issue paper 7: municipal finance<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">CEDEUS<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">\u00c1lvaro Javier Rom\u00e1n Castillo<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Issue paper 7: municipal finance<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">CEDEUS<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">\u00c1lvaro Javier Rom\u00e1n Castillo<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Mercantilizaci\u00f3n y despolitizaci\u00f3n: bases de una dif\u00edcil gobernanza en torno al salm\u00f3n<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Salmonexpert, 38(6), 46-50<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">\u00c1lvaro Javier Rom\u00e1n Castillo<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Mercantilizaci\u00f3n y despolitizaci\u00f3n: bases de una dif\u00edcil gobernanza en torno al salm\u00f3n<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Salmonexpert, 38(6), 46-50<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">\u00c1lvaro Javier Rom\u00e1n Castillo<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> El Mostrador<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">La urgencia de reparaci\u00f3n para el territorio Mapuche-Lafkenche<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Columna para El Mostrador Digital<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">https:\/\/www.elmostrador.cl\/noticias\/opinion\/columnas\/2025\/10\/01\/la-urgencia-de-reparacion-para-el-territorio-mapuche-lafkenche\/<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Adriana Suarez Delucchi<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-bullhorn fa-fw\"><\/i> El Mostrador<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">La urgencia de reparaci\u00f3n para el territorio Mapuche-Lafkenche<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Columna para El Mostrador Digital<\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">https:\/\/www.elmostrador.cl\/noticias\/opinion\/columnas\/2025\/10\/01\/la-urgencia-de-reparacion-para-el-territorio-mapuche-lafkenche\/<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Adriana Suarez Delucchi<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Informe Fase 1 y 4: Caracterizaci\u00f3n R\u00e9gimen Socio-T\u00e9cnico del Sistema Energ\u00e9tico de la Regi\u00f3n de Ays\u00e9n<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jos\u00e9 Barrena Ruiz, Sebastian Ibarra, Clara Irarr\u00e1zabal, Andr\u00e9s Monckeberg, Trace Gale, Luz Cardona<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Informe Fase 1 y 4: Caracterizaci\u00f3n R\u00e9gimen Socio-T\u00e9cnico del Sistema Energ\u00e9tico de la Regi\u00f3n de Ays\u00e9n<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Jos\u00e9 Barrena Ruiz, Sebastian Ibarra, Clara Irarr\u00e1zabal, Andr\u00e9s Monckeberg, Trace Gale, Luz Cardona<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Informe Final Segundo Ciclo Proyecto Semilla Bosque Modelo Panguipulli Tomo II: Delimitaci\u00f3n del Paisaje<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Maite Hernando Arrese, Jos\u00e9 Barrena Ruiz<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Informe Final Segundo Ciclo Proyecto Semilla Bosque Modelo Panguipulli Tomo II: Delimitaci\u00f3n del Paisaje<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Maite Hernando Arrese, Jos\u00e9 Barrena Ruiz<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Indicadores de Servicios Ecosist\u00e9micos. Una Revisi\u00f3n y An\u00e1lisis de su Calidad<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Laura Nahuelhual, Pedro Laterra, Jos\u00e9 Barrena Ruiz<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Indicadores de Servicios Ecosist\u00e9micos. Una Revisi\u00f3n y An\u00e1lisis de su Calidad<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-align-left fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Descripci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n            \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Tipo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-lg-none border-bottom pb-lg-0 pb-2\">\n            <small class=\"text-muted\">Laura Nahuelhual, Pedro Laterra, Jos\u00e9 Barrena Ruiz<\/small>\n        <\/div>\n\n        <!-- <div class=\"col-12 col-sm-6 col-lg-3\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-9\">\n            <small class=\"text-muted\"><\/small>\n        <\/div> -->\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>[\/vc_tta_section][vc_tta_section title=&#8221;Contacto&#8221; tab_id=&#8221;contacto&#8221;][\/vc_tta_section][\/vc_tta_tabs][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"featured_media":24963,"parent":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"institute_academics":[7],"profile_academics":[14],"class_list":["post-7928","academics","type-academics","status-publish","has-post-thumbnail","hentry","institute_academics-instituto-de-ciencias-de-la-educacion","profile_academics-academico"],"rut_academico":"26195708-6","mail_academico":"ngaire.honey@uoh.cl","n_proyectos":"5","n_publicaciones":"7","n_libros":"0","n_cap_libros":"2","n_otros_libros":"2","acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ngaire Honey - Investigaci\u00f3n<\/title>\n<meta name=\"description\" content=\"Profesora Asistente del Instituto de Ciencias de la Educaci\u00f3n de la Universidad Estatal de O&#039;Higgins.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uoh.cl\/investigacion\/academico\/ngaire-honey\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ngaire Honey - Investigaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Profesora Asistente del Instituto de Ciencias de la Educaci\u00f3n de la Universidad Estatal de O&#039;Higgins.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/investigacion\/academico\/ngaire-honey\/\" \/>\n<meta property=\"og:site_name\" content=\"Investigaci\u00f3n\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T10:17:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2023\/03\/Ngaire-Honey-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/academico\/ngaire-honey\/\",\"url\":\"https:\/\/www.uoh.cl\/investigacion\/academico\/ngaire-honey\/\",\"name\":\"Ngaire Honey - Investigaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/academico\/ngaire-honey\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/academico\/ngaire-honey\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2023\/03\/Ngaire-Honey-1.png\",\"datePublished\":\"2023-03-23T18:10:13+00:00\",\"dateModified\":\"2026-05-13T10:17:26+00:00\",\"description\":\"Profesora Asistente del Instituto de Ciencias de la Educaci\u00f3n de la Universidad Estatal de O'Higgins.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/academico\/ngaire-honey\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uoh.cl\/investigacion\/academico\/ngaire-honey\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/academico\/ngaire-honey\/#primaryimage\",\"url\":\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2023\/03\/Ngaire-Honey-1.png\",\"contentUrl\":\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2023\/03\/Ngaire-Honey-1.png\",\"width\":1000,\"height\":1000,\"caption\":\"Ngaire Honey\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/academico\/ngaire-honey\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Acad\u00e9micos\",\"item\":\"https:\/\/www.uoh.cl\/investigacion\/academico\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ngaire Honey\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/#website\",\"url\":\"https:\/\/www.uoh.cl\/investigacion\/\",\"name\":\"Investigaci\u00f3n\",\"description\":\"Sitio web de investigaci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uoh.cl\/investigacion\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ngaire Honey - Investigaci\u00f3n","description":"Profesora Asistente del Instituto de Ciencias de la Educaci\u00f3n de la Universidad Estatal de O'Higgins.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uoh.cl\/investigacion\/academico\/ngaire-honey\/","og_locale":"es_ES","og_type":"article","og_title":"Ngaire Honey - Investigaci\u00f3n","og_description":"Profesora Asistente del Instituto de Ciencias de la Educaci\u00f3n de la Universidad Estatal de O'Higgins.","og_url":"https:\/\/www.uoh.cl\/investigacion\/academico\/ngaire-honey\/","og_site_name":"Investigaci\u00f3n","article_modified_time":"2026-05-13T10:17:26+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2023\/03\/Ngaire-Honey-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/investigacion\/academico\/ngaire-honey\/","url":"https:\/\/www.uoh.cl\/investigacion\/academico\/ngaire-honey\/","name":"Ngaire Honey - Investigaci\u00f3n","isPartOf":{"@id":"https:\/\/www.uoh.cl\/investigacion\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uoh.cl\/investigacion\/academico\/ngaire-honey\/#primaryimage"},"image":{"@id":"https:\/\/www.uoh.cl\/investigacion\/academico\/ngaire-honey\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2023\/03\/Ngaire-Honey-1.png","datePublished":"2023-03-23T18:10:13+00:00","dateModified":"2026-05-13T10:17:26+00:00","description":"Profesora Asistente del Instituto de Ciencias de la Educaci\u00f3n de la Universidad Estatal de O'Higgins.","breadcrumb":{"@id":"https:\/\/www.uoh.cl\/investigacion\/academico\/ngaire-honey\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/investigacion\/academico\/ngaire-honey\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/investigacion\/academico\/ngaire-honey\/#primaryimage","url":"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2023\/03\/Ngaire-Honey-1.png","contentUrl":"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2023\/03\/Ngaire-Honey-1.png","width":1000,"height":1000,"caption":"Ngaire Honey"},{"@type":"BreadcrumbList","@id":"https:\/\/www.uoh.cl\/investigacion\/academico\/ngaire-honey\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Acad\u00e9micos","item":"https:\/\/www.uoh.cl\/investigacion\/academico\/"},{"@type":"ListItem","position":2,"name":"Ngaire Honey"}]},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/investigacion\/#website","url":"https:\/\/www.uoh.cl\/investigacion\/","name":"Investigaci\u00f3n","description":"Sitio web de investigaci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/investigacion\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/academics\/7928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/academics"}],"about":[{"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/types\/academics"}],"version-history":[{"count":6,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/academics\/7928\/revisions"}],"predecessor-version":[{"id":20612,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/academics\/7928\/revisions\/20612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/media\/24963"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/media?parent=7928"}],"wp:term":[{"taxonomy":"institute_academics","embeddable":true,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/institute_academics?post=7928"},{"taxonomy":"profile_academics","embeddable":true,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/profile_academics?post=7928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}