
{"id":781,"date":"2022-04-29T13:48:19","date_gmt":"2022-04-29T16:48:19","guid":{"rendered":"https:\/\/www.uoh.cl\/investigacion\/academico\/maria-victoria-martinez-videla-2\/"},"modified":"2026-05-12T20:02:31","modified_gmt":"2026-05-12T23:02:31","slug":"jose-mela","status":"publish","type":"academics","link":"https:\/\/www.uoh.cl\/investigacion\/academico\/jose-mela\/","title":{"rendered":"Jos\u00e9 Mela"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1650056176159{padding-top: 3rem !important;}&#8221;][vc_row][vc_column][vc_wp_custommenu nav_menu=&#8221;5&#8243;]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/investigacion\"><span itemprop=\"name\">Investigaci\u00f3n<\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/investigacion\"><span itemprop=\"name\">Investigaci\u00f3n<\/span><\/a><meta itemprop=\"position\" content=\"3\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/investigacion\/academicos\"><span itemprop=\"name\">Acad\u00e9micos<\/span><\/a><meta itemprop=\"position\" content=\"4\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Jos\u00e9 Mela <\/span><meta itemprop=\"position\" content=\"5\" \/><\/ol><\/div><ul class=\"p-0 list-style-none d-inline-block\"><li class=\"p-0\"><a href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\" class=\"px-1 py-2\">\n                            Instituto de Ciencias de la Educaci\u00f3n\n                        <\/a><\/li><\/ul><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block big\">Jos\u00e9 Mela<em class=\"position__title\"> <span>\u25cf<\/span> Profesor Asociado<\/em><\/h1><\/div>[vc_row_inner el_class=&#8221;border-separator m-0 mt-4&#8243;][vc_column_inner width=&#8221;1\/6&#8243;]<div class=\"vc_single_image-wrapper vc_box_rounded  vc_box_border_grey\"><img decoding=\"async\" width=\"1024\" height=\"1024\" data-src=\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2022\/04\/Jose-Mela-1-1024x1024.jpg\" class=\"attachment-large size-large wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2022\/04\/Jose-Mela-1-1024x1024.jpg 1024w, https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2022\/04\/Jose-Mela-1-300x300.jpg 300w, https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2022\/04\/Jose-Mela-1-150x150.jpg 150w, https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2022\/04\/Jose-Mela-1-768x768.jpg 768w, https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2022\/04\/Jose-Mela-1-600x600.jpg 600w, https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2022\/04\/Jose-Mela-1.jpg 1080w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/1024;\" \/><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;2\/3&#8243;]<div class=\"block--info\">\n                                <div class=\"sub_title__grade\">Grado Acad\u00e9mico<\/div>\n                                <h3>Doctor en Artes y Educaci\u00f3n, U. Barcelona., Mag\u00edster en Educaci\u00f3n Interdisciplinar de las Artes, U. de Barcelona.<\/h3> <\/div><div class=\"block--info\">\n                                <div class=\"sub_title__grade\">T\u00edtulo(s) Profesional<\/div>\n                                <h3>Profesor de Artes Pl\u00e1sticas.<\/h3> <\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;]<div class=\"uoh_social_network_component uoh_row col-12 justify-content-end m-0 p-0\"> <div class=\"icon__facebook-share-button\">\n                       <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.uoh.cl\/investigacion\/academico\/jose-mela\/\" target=\"_blank\"> <div class=\"icon__facebook-svg\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22.4px\" height=\"48.3px\" viewBox=\"0 0 22.4 48.3\" style=\"overflow:visible;enable-background:new 0 0 22.4 48.3;\" xml:space=\"preserve\">\n                <defs>\n                <\/defs>\n                <path class=\"st0\" d=\"M22.4,15.6h-7.6v-5c0-1.9,1.2-2.3,2.1-2.3c0.9,0,5.4,0,5.4,0V0l-7.4,0C6.6,0,4.8,6.2,4.8,10.1v5.5H0v8.5h4.8\n                    c0,10.9,0,24.1,0,24.1h10c0,0,0-13.3,0-24.1h6.8L22.4,15.6z\"><\/path>\n                <\/svg><\/a><\/div>\n                    <\/div><div class=\"icon__twitter-share-button\">\n                        <div class=\"icon__twitter-svg\"><a target=\"_blank\" href=\"http:\/\/twitter.com\/share?url=https:\/\/www.uoh.cl\/investigacion\/academico\/jose-mela\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/a><\/div>\n                        <\/div><div class=\"icon__linkedin-share-button\">\n                        <div class=\"icon__linkedin-svg\">\n                        <a target=\"__blank\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.uoh.cl\/investigacion\/academico\/jose-mela\/\"><svg enable-background=\"new 0 0 100 100\" height=\"100px\" id=\"Layer_1\" version=\"1.1\" viewBox=\"0 0 100 100\" width=\"100px\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><circle cx=\"50\" cy=\"50\" fill=\"#ccc\" r=\"45\"\/><g id=\"LinkedIn_1_\"><rect fill=\"#FFFFFF\" height=\"24.361\" width=\"7.69\" x=\"31.271\" y=\"43.569\"\/><path d=\"M59.968,43.334c-4.406,0-7.165,2.387-7.677,4.058v-3.823h-8.636c0.109,2.03,0,24.361,0,24.361h8.636    V54.748c0-0.733-0.034-1.465,0.19-1.991c0.594-1.464,1.869-2.985,4.162-2.985c2.998,0,4.361,2.253,4.361,5.552V67.93h8.721V54.384    C69.726,46.839,65.432,43.334,59.968,43.334z\" fill=\"#FFFFFF\"\/><path d=\"M34.973,32.069c-2.839,0-4.696,1.823-4.696,4.229c0,2.361,1.804,4.224,4.589,4.224h0.054    c2.891,0,4.69-1.869,4.69-4.229C39.555,33.888,37.81,32.069,34.973,32.069z\" fill=\"#FFFFFF\"\/><\/g><\/g><\/svg><\/a><\/div>\n\n            <\/div><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650239278498{background-color: #ffffff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center&#8221;][vc_column][vc_row_inner][vc_column_inner width=&#8221;5\/6&#8243;]<div class=\"uoh_title_component-container\"><h4 class=\"title title--ms d-inline-block title--decorator  small\">Descripci\u00f3n<\/h4><\/div><p class=\"info-headings mb-2 text-left mt-4 mt-md-2\">Finaliz\u00f3 sus estudios de M\u00e1ster en Educaci\u00f3n Interdisciplinar de las Artes en la Universidad de Barcelona en el a\u00f1o 2012, para continuar estudios de doctorado en Artes y Educaci\u00f3n en la misma instituci\u00f3n. Se ha dedicado a investigar sobre la identidad mapuche urbana en adolescentes, a trav\u00e9s del uso de metodolog\u00edas visuales, como la fotograf\u00eda, para reunir evidencias y evocar nuevos significados. Actualmente, se dedica a la creaci\u00f3n art\u00edstica, la docencia universitaria y a escribir sobre la Investigaci\u00f3n Basada en las Artes, Interculturalidad y los diversos procesos de construcci\u00f3n identitaria de pueblos originarios como el mapuche.<\/p>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650056119592{background-color: #ffffff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5 pb-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-start&#8221;][vc_column width=&#8221;1\/6&#8243; el_class=&#8221;p-0&#8243;]<div class=\"uoh_link_component pe-4 d-inline-block py-1 button_icon inline\"><i class=\"me-2 fas fa-newspaper\" style=\"color: #42a0f8\"><\/i><span>Publicaciones<\/span><\/div><div class=\"wpb_text_column wpb_content_element  citas mb-3 pb-3\"><div class=\"wpb_wrapper\"><p>10<\/p><\/div><\/div><div class=\"uoh_link_component pe-4 d-inline-block py-1 button_icon inline\"><i class=\"me-2 fas fa-project-diagram\" style=\"color: #42a0f8\"><\/i><span>Proyectos<\/span><\/div><div class=\"wpb_text_column wpb_content_element  citas mb-3 pb-3\"><div class=\"wpb_wrapper\"><p>16<\/p><\/div><\/div><div class=\"uoh_link_component pe-4 d-inline-block py-1 button_icon inline\"><i class=\"me-2 fas fa-book\" style=\"color: #42a0f8\"><\/i><span>Libros y Monograf\u00edas<\/span><\/div><div class=\"wpb_text_column wpb_content_element  citas mb-3 pb-3\"><div class=\"wpb_wrapper\"><p>1<\/p><\/div><\/div><div class=\"uoh_link_component pe-4 d-inline-block py-1 button_icon inline\"><i class=\"me-2 fas fa-book-bookmark\" style=\"color: #42a0f8\"><\/i><span>Cap\u00edtulos de Libros<\/span><\/div><div class=\"wpb_text_column wpb_content_element  citas mb-3 pb-3\"><div class=\"wpb_wrapper\"><p>8<\/p><\/div><\/div>[\/vc_column][vc_column width=&#8221;5\/6&#8243;][vc_tta_tabs active_section=&#8221;1&#8243; el_class=&#8221;tabs-inner-academic&#8221;][vc_tta_section title=&#8221;Publicaciones&#8221; tab_id=&#8221;publicaciones&#8221;]<link rel=\"stylesheet\" id=\"font-awesome-css\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.5.1\/css\/all.min.css\" type=\"text\/css\" media=\"all\"><div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0 px-md-0 \"><\/div><\/div><div class=\"content-holder row m-0 p-0 aling-items-center pt-5 pb-5 \"><div class=\"row  large--swipper-content p-0 \"><div class=\"\"><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-newspaper fa-fw\"><\/i> REVISTA Revista Brasileira de Educa\u00e7\u00e3o<\/li><li class=\"p-0\"><i class=\"fa fa-regular fa-calendar fa-fw\"><\/i> 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><h3 class=\"small-space title-ss text-decoration-none m-0\">Educaci\u00f3n art\u00edstica en ruralidad: an\u00e1lisis de experiencias pedag\u00f3gicas en escuelas b\u00e1sicas de O\u0092Higgins, antes y durante la pandemia por Covid-19<\/h3><br><i class=\"fas fa-solid fa-users fa-fw me-2\"><\/i><small class=\"text-muted\"> \u2022 Jos\u00e9 Israel Mela Contreras \u2022  Catalina Montenegro \u2022  Valeria Carvallo <\/small><br><p class=\"text-muted pt-3 position-relative\" style=\"z-index:2;\"><a href=\"http:\/\/dx.doi.org\/10.1590\/S1413-24782025300040\" target=\"_blank\"><i class=\"fas fa-solid fa-link fa-fw\"><\/i> http:\/\/dx.doi.org\/10.1590\/S1413-24782025300040<\/a><\/small><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-newspaper fa-fw\"><\/i> REVISTA Revista Pr\u00e2ksis<\/li><li class=\"p-0\"><i class=\"fa fa-regular fa-calendar fa-fw\"><\/i> 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><h3 class=\"small-space title-ss text-decoration-none m-0\">Abordajes metodol\u00f3gicos en las pr\u00e1cticas art\u00edsticas colaborativas en Chile<\/h3><br><i class=\"fas fa-solid fa-users fa-fw me-2\"><\/i><small class=\"text-muted\"> \u2022 Mar\u00eda Rosario de Lourdes Garc\u00eda-Huidobro Munita \u2022  Jos\u00e9 Israel Mela Contreras <\/small><br><p class=\"text-muted pt-3 position-relative\" style=\"z-index:2;\"><a href=\"http:\/\/dx.doi.org\/10.25112\/rpr.v1.3980\" target=\"_blank\"><i class=\"fas fa-solid fa-link fa-fw\"><\/i> http:\/\/dx.doi.org\/10.25112\/rpr.v1.3980<\/a><\/small><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-newspaper fa-fw\"><\/i> REVISTA Estudios Pedag\u00f3gicos<\/li><li class=\"p-0\"><i class=\"fa fa-regular fa-calendar fa-fw\"><\/i> 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><h3 class=\"small-space title-ss text-decoration-none m-0\">Ense\u00f1anza art\u00edstica y d\u00e9ficit de profesorado cualificado en escuelas p\u00fablicas de O\u0092Higgins, Chile<\/h3><br><i class=\"fas fa-solid fa-users fa-fw me-2\"><\/i><small class=\"text-muted\"> \u2022 Jos\u00e9 Israel Mela Contreras \u2022  Paulina Guti\u00e9rrez <\/small><br><p class=\"text-muted pt-3 position-relative\" style=\"z-index:2;\"><a href=\"http:\/\/dx.doi.org\/http:\/\/revistas.uach.cl\/index.php\/estped\/article\/view\/8103\" target=\"_blank\"><i class=\"fas fa-solid fa-link fa-fw\"><\/i> http:\/\/dx.doi.org\/http:\/\/revistas.uach.cl\/index.php\/estped\/article\/view\/8103<\/a><\/small><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-newspaper fa-fw\"><\/i> REVISTA Anagramas Rumbos y Sentidos de la Comunicaci\u00f3n<\/li><li class=\"p-0\"><i class=\"fa fa-regular fa-calendar fa-fw\"><\/i> 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><h3 class=\"small-space title-ss text-decoration-none m-0\">Cine, diversidad e infancia: el proyecto Cineduka en escuelas b\u00e1sicas chilenas<\/h3><br><i class=\"fas fa-solid fa-users fa-fw me-2\"><\/i><small class=\"text-muted\"> \u2022 Jos\u00e9 Israel Mela Contreras \u2022  Josep Torell\u00f3 (Universidad Polit\u00e9cnica de Barcelona) \u2022  Daniela Cobos (Universidad de Chile) <\/small><br><p class=\"text-muted pt-3 position-relative\" style=\"z-index:2;\"><a href=\"http:\/\/dx.doi.org\/https:\/\/revistas.udem.edu.co\/index.php\/anagramas\/article\/view\/3977\" target=\"_blank\"><i class=\"fas fa-solid fa-link fa-fw\"><\/i> http:\/\/dx.doi.org\/https:\/\/revistas.udem.edu.co\/index.php\/anagramas\/article\/view\/3977<\/a><\/small><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-newspaper fa-fw\"><\/i> REVISTA Cuadernos De M\u00fasica, Artes Visuales y Artes Esc\u00e9nicas (Publindex y Scopus Q4)<\/li><li class=\"p-0\"><i class=\"fa fa-regular fa-calendar fa-fw\"><\/i> 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><h3 class=\"small-space title-ss text-decoration-none m-0\">Autorrepresentaci\u00f3n identitaria a trav\u00e9s de las artes visuales: la experiencia del Taller de Fotograf\u00eda Infantil Mapuche<\/h3><br><i class=\"fas fa-solid fa-users fa-fw me-2\"><\/i><small class=\"text-muted\"> \u2022 Jos\u00e9 Israel Mela Contreras <\/small><br><p class=\"text-muted pt-3 position-relative\" style=\"z-index:2;\"><a href=\"http:\/\/dx.doi.org\/10.11144\/javeriana.mavae16-2.arit\" target=\"_blank\"><i class=\"fas fa-solid fa-link fa-fw\"><\/i> http:\/\/dx.doi.org\/10.11144\/javeriana.mavae16-2.arit<\/a><\/small><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-newspaper fa-fw\"><\/i> REVISTA Visual Anthropology (Scopus - Q2 - Q3)<\/li><li class=\"p-0\"><i class=\"fa fa-regular fa-calendar fa-fw\"><\/i> 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><h3 class=\"small-space title-ss text-decoration-none m-0\">The Azent\u00fan Photography Workshop: a proposal for self-representing the urban Mapuche teenagers in Santiago de Chile<\/h3><br><i class=\"fas fa-solid fa-users fa-fw me-2\"><\/i><small class=\"text-muted\"> \u2022 Jos\u00e9 Israel Mela Contreras <\/small><br><p class=\"text-muted pt-3 position-relative\" style=\"z-index:2;\"><a href=\"http:\/\/dx.doi.org\/10.1080\/08949468.2020.1824974\" target=\"_blank\"><i class=\"fas fa-solid fa-link fa-fw\"><\/i> http:\/\/dx.doi.org\/10.1080\/08949468.2020.1824974<\/a><\/small><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-newspaper fa-fw\"><\/i> REVISTA Artseduca (Scopus)<\/li><li class=\"p-0\"><i class=\"fa fa-regular fa-calendar fa-fw\"><\/i> 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><h3 class=\"small-space title-ss text-decoration-none m-0\">Educaci\u00f3n art\u00edstica y el desarrollo de competencias interculturales: una propuesta para el fortalecimiento de la diversidad cultural en la ense\u00f1anza b\u00e1sica chilena<\/h3><br><i class=\"fas fa-solid fa-users fa-fw me-2\"><\/i><small class=\"text-muted\"> \u2022 Jos\u00e9 Israel Mela Contreras <\/small><br><p class=\"text-muted pt-3 position-relative\" style=\"z-index:2;\"><a href=\"http:\/\/dx.doi.org\/10.6035\/Artseduca.2020.27.15\" target=\"_blank\"><i class=\"fas fa-solid fa-link fa-fw\"><\/i> http:\/\/dx.doi.org\/10.6035\/Artseduca.2020.27.15<\/a><\/small><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-newspaper fa-fw\"><\/i> REVISTA Aisthesis: revista chilena de investigaciones est\u00e9ticas (Scopus - Q2)<\/li><li class=\"p-0\"><i class=\"fa fa-regular fa-calendar fa-fw\"><\/i> 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><h3 class=\"small-space title-ss text-decoration-none m-0\">El Taller de Fotograf\u00eda Azent\u00fan con adolescentes mapuche de Santiago. Una propuesta fotogr\u00e1fica-perform\u00e1tica para recrear una identidad visual ind\u00edgena y urbana en el Museo Hist\u00f3rico Nacional de Chile<\/h3><br><i class=\"fas fa-solid fa-users fa-fw me-2\"><\/i><small class=\"text-muted\"> \u2022 Jos\u00e9 Israel Mela Contreras <\/small><br><p class=\"text-muted pt-3 position-relative\" style=\"z-index:2;\"><a href=\"http:\/\/dx.doi.org\/10.7764\/67.10\" target=\"_blank\"><i class=\"fas fa-solid fa-link fa-fw\"><\/i> http:\/\/dx.doi.org\/10.7764\/67.10<\/a><\/small><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-newspaper fa-fw\"><\/i> REVISTA MODULEMA. Revista cient\u00edfica sobre Diversidad Cultural (Latindex-Erihplus)<\/li><li class=\"p-0\"><i class=\"fa fa-regular fa-calendar fa-fw\"><\/i> 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><h3 class=\"small-space title-ss text-decoration-none m-0\">EDUCACI\u00d3N EN COMPETENCIAS INTERCULTURALES PARA LA DIVERSIDAD CULTURAL, \u00c9TNICA Y SEXUAL. LA EXPERIENCIA DEL PROYECTO &quot;CINEDUKA&quot; EN ESCUELAS B\u00c1SICAS CHILENAS<\/h3><br><i class=\"fas fa-solid fa-users fa-fw me-2\"><\/i><small class=\"text-muted\"> \u2022 Jos\u00e9 Israel Mela Contreras <\/small><br><p class=\"text-muted pt-3 position-relative\" style=\"z-index:2;\"><a href=\"http:\/\/dx.doi.org\/10.30827\/modulema.v4i0.15156\" target=\"_blank\"><i class=\"fas fa-solid fa-link fa-fw\"><\/i> http:\/\/dx.doi.org\/10.30827\/modulema.v4i0.15156<\/a><\/small><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-newspaper fa-fw\"><\/i> REVISTA P\u00e1ginas de Educaci\u00f3n (Scielo)<\/li><li class=\"p-0\"><i class=\"fa fa-regular fa-calendar fa-fw\"><\/i> 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><h3 class=\"small-space title-ss text-decoration-none m-0\">La investigaci\u00f3n basada en las artes: an\u00e1lisis de su uso y experiencia docente en el colegio Hispanoamericano<\/h3><br><i class=\"fas fa-solid fa-users fa-fw me-2\"><\/i><small class=\"text-muted\"> \u2022 Jos\u00e9 Israel Mela Contreras <\/small><br><p class=\"text-muted pt-3 position-relative\" style=\"z-index:2;\"><a href=\"http:\/\/dx.doi.org\/10.22235\/pe.v12i2.1839\" target=\"_blank\"><i class=\"fas fa-solid fa-link fa-fw\"><\/i> http:\/\/dx.doi.org\/10.22235\/pe.v12i2.1839<\/a><\/small><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>[\/vc_tta_section][vc_tta_section title=&#8221;Proyectos&#8221; tab_id=&#8221;proyectos&#8221;]<link rel=\"stylesheet\" id=\"font-awesome-css\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.5.1\/css\/all.min.css\" type=\"text\/css\" media=\"all\"><div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0 px-md-0 \"><\/div><\/div><div class=\"content-holder row m-0 p-0 aling-items-center pt-5 pb-5 \"><div class=\"row  large--swipper-content p-0 \"><div class=\"\"><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2026 - Mayo 2029<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26379\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortaleciendo la protecci\u00f3n del humedal Bucalemu: Transferencia de herramientas para la gesti\u00f3n, monitoreo y desarrollo sostenible\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26379\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26379\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En el marco del diagn\u00f3stico territorial participativo realizado para el humedal Bucalemu, los beneficiarios identificaron necesidades prioritarias para mejorar la gesti\u00f3n integral del humedal, considerando su importancia como \u00e1rea protegida y las actividades antr\u00f3picas asociadas. Entre las propuestas m\u00e1s destacadas se encuentran:\r\n1.\tFortalecer la gobernanza local: Los actores locales se\u00f1alaron la necesidad de establecer un plan de gesti\u00f3n municipal que permita una mejor coordinaci\u00f3n entre las partes interesadas y que priorice acciones concretas para la conservaci\u00f3n y uso sostenible del humedal.\r\n2.\tImplementar programas educativos y de difusi\u00f3n: Se propuso incluir a la comunidad y a los colegios locales en actividades de educaci\u00f3n ambiental, sensibilizaci\u00f3n sobre la importancia del humedal y difusi\u00f3n de buenas pr\u00e1cticas de manejo sostenible.\r\n3.\tCapacitaci\u00f3n en monitoreo ambiental: Los participantes destacaron la necesidad de contar con herramientas y conocimientos t\u00e9cnicos para monitorear y gestionar el humedal de manera aut\u00f3noma y sostenible.\r\n4.\tZonificaci\u00f3n y regulaci\u00f3n de actividades: Identificaron la importancia de delimitar \u00e1reas para uso tur\u00edstico, conservaci\u00f3n estricta y actividades productivas de bajo impacto, para minimizar los efectos de las actividades humanas sobre el ecosistema.\r\nLa Universidad de O\u0092Higgins se compromete a incorporar estas propuestas como ejes centrales en el proyecto, apoyando al municipio en el desarrollo de su plan de gesti\u00f3n mediante las siguientes acciones concretas:\r\n\u0095\tGenerar informaci\u00f3n cient\u00edfica confiable a trav\u00e9s del Laboratorio de Ecosistemas de Humedales, la cual servir\u00e1 como base t\u00e9cnica para el diagn\u00f3stico sectorial y la planificaci\u00f3n.\r\n\u0095\tFacilitar talleres participativos para definir los objetos de conservaci\u00f3n y metas del plan, as\u00ed como estrategias espec\u00edficas para su implementaci\u00f3n.\r\n\u0095\tTransferir herramientas de monitoreo ambiental y capacitar a actores locales, asegurando que puedan realizar un seguimiento continuo de los indicadores del plan.\r\n\u0095\tDise\u00f1ar materiales educativos y desarrollar campa\u00f1as de difusi\u00f3n que fortalezcan la conexi\u00f3n entre la comunidad y el humedal.\r\n\"Como resultado del proceso de diagn\u00f3stico territorial participativo, los beneficiarios identificaron diversas iniciativas clave para fortalecer la gesti\u00f3n del humedal Bucalemu y promover su desarrollo sostenible. Entre las propuestas m\u00e1s destacadas se incluyen:\r\n1.\tCharlas informativas: Estas actividades sensibilizar\u00e1n a la comunidad sobre la importancia del humedal, destacando su biodiversidad y los beneficios de su conservaci\u00f3n. Las charlas incluir\u00e1n informaci\u00f3n t\u00e9cnica y relevante para fomentar un manejo m\u00e1s sostenible del ecosistema.\r\n2.\tProgramas educativos con colegios locales: Se implementar\u00e1n talleres pr\u00e1cticos y actividades educativas para involucrar a estudiantes en la conservaci\u00f3n del humedal, inspirando un sentido de pertenencia y responsabilidad hacia el ecosistema.\r\n3.\tCapacitaciones especializadas: Funcionarios municipales y algunos actores clases recibir\u00e1n formaci\u00f3n en gesti\u00f3n sostenible, incluyendo monitoreo ambiental y pr\u00e1cticas de bajo impacto, para fortalecer sus capacidades en el manejo del humedal.\r\n4.\tActividades de difusi\u00f3n y sensibilizaci\u00f3n: Campa\u00f1as de comunicaci\u00f3n y material informativo promover\u00e1n el turismo responsable y orientar\u00e1n a los visitantes hacia pr\u00e1cticas respetuosas con el ecosistema.\r\n5.\tFortalecimiento de los peque\u00f1os productores locales: Se desarrollar\u00e1n actividades espec\u00edficas para capacitar a productores en pr\u00e1cticas sostenibles y promocionar sus productos como parte de una estrategia de turismo responsable, fortaleciendo su conexi\u00f3n con el humedal.\r\n\r\nEl Laboratorio de Ecosistemas de Humedales de la Universidad de O\u0092Higgins aportar\u00e1 informaci\u00f3n cient\u00edfica y herramientas t\u00e9cnicas esenciales para sustentar estas iniciativas, especialmente en lo relacionado con el diagn\u00f3stico del ecosistema, el dise\u00f1o de protocolos de monitoreo y la generaci\u00f3n de indicadores clave para evaluar el impacto de las acciones implementadas. De esta forma, la Universidad de O\u0092Higgins se compromete a incorporar estas propuestas en la iniciativa, asegurando su implementaci\u00f3n como parte de una estrategia integral de transferencia de conocimiento y gesti\u00f3n sostenible en colaboraci\u00f3n con los actores locales y otras instituciones relevantes[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1261124<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2026 - Marzo 2029<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27125\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Los cuidados en perspectiva territorial: estudio comparativo sobre corresponsabilidad de g\u00e9nero, salud mental y uso del tiempo en la agricultura familiar\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27125\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27125\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto estudia los cuidados en perspectiva territorial por medio de un estudio comparativo sobre corresponsabilidad de g\u00e9nero, salud mental y uso del tiempo en la agricultura familiar, especialmente en el caso de mujeres campesinas en 4 regiones del pa\u00eds: Arica y Tarapac\u00e1, Antofagasta, Metropolitana y Araucan\u00eda.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26950\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Charting Colon Cancer\u0092s Molecular Axes via an Integrated Multi-Omic Atlas and AI-Driven Histopathology\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26950\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26950\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Chile is facing one of the steepest increases in Colorectal cancer (CRC) incidence and mortality in the Southern Cone, with\r\nthe greatest surge occurring in adults &#8804; 50 years. Incidence is lowest in the far north and increases toward the\r\nsouth-central regions, mirroring a gradient in Aymara-Mapuche Native-American ancestry, an axis largely absent from the\r\nEuropean reference cohorts that guide modern precision oncology. To fill this gap, we propose a four-year project to create\r\nthe first Chile-specific, multi-omic and histopathological atlas of CRC and to explore ancestry-aware, AI-assisted\r\ndiagnostics.\r\nRationale and Hypothesis.\r\nWe hypothesise that Chilean CRC shows (i) unique, ancestry-driven molecular patterns that differ from European tumors;\r\n(ii) AI models can detect these patterns directly on routine whole-slide images, and (iii) they shape distinct evolutionary\r\npaths in early- versus late-onset disease.\r\nSpecific objectives.\r\nMolecular landscape & heterogeneity: Produce single-gland long-read WGS, methylome, and transcriptome profiles for\r\n100 tumors (30 early-onset, 70 late-onset; &#8805;30\u00d7 coverage, &#8805;50 % purity).\r\nAncestry impact: Phase somatic alterations by local ancestry and contrast their frequencies with European CRC\r\ngenomes (TCGA, PCAWG).\r\nAI-enhanced histopathology: Train and externally validate multi-instance-learning (MIL) models that predict microsatellite\r\ninstability, driver mutations, and whole-genome doubling from matched WSIs, targeting AUC &#8805; 0.80 (pilot: AUC &#8805; 0.85 for\r\nwhole-genome doubling on TCGA WSIs).\r\nEvolutionary trajectories: Multi-region sequence early-onset and late-onset tumors, reconstruct their clonal phylogenies,\r\nand contrast the resulting evolutionary patterns between the two age groups.\r\nTeam capacity & resources. Computational biologist Alex Di Genova (genomics & AI), pathologist Juan Carlos Araya\r\n(digital pathology), and gastro-immunologist Tamara P\u00e9rez-Jeldres (clinical phenotyping) have prospective access to >220\r\nnew CRC resections and >1,800 registry entries each year. A biobank already houses 100 well-annotated tumour\r\nspecimens from hospitals in Santiago and the O\u0092Higgins Region, ready for immediate sequencing and imaging.\r\nAs a team we are delivering important results as (i) the generation of the first telomere-to-telomere Chilean genome,\r\nestablishing a population-specific reference; (ii) sequenced >270 high-coverage whole genomes of chileans individuals (70\r\nhealthy donors, 120 hereditary-breast-cancer cases, 80 primary gallbladder tumors); iii) built the first multi-omic atlas of\r\ngallbladder cancer by integrating our data with Korean (n = 94) and Indian (n = 64) cohorts, uncovering a Chile-enriched\r\nproliferative phenotype; and (iv) developed CRAB-MIL, a weakly supervised deep-learning framework that predicts\r\nwhole-genome doubling from routine H&E slides with an AUC > 0.85 and provides attention maps for interpretability. These\r\naccomplishments demonstrate our ability to generate, integrate, and clinically interpret large-scale genomic and AI\r\ndatasets\u0097capabilities directly transferable to Chilean CRC. International collaborators Ana\u00efs Baudot (Marseille) and Luis\r\nZapata (Institute of Cancer Research, London) further contribute multi-omic network analysis and evolutionary-genomics\r\nexpertise, respectively.\r\nInterdisciplinary workflow. Clinical phenotyping, computational histopathology, PromethION sequencing, and Nextflow\r\nharmonisation feed ancestry-aware genomic analyses; attention-based models are fine-tuned on TCGA and Chilean WSIs;\r\ncomputational, pathology, and gastroenterology teams jointly review outputs to prioritise clinically relevant signals. All\r\nvariant calls, methylomes, expression matrices, AI prediction, and metadata will be released through an open and intuitive\r\nTumorMap portal.\r\nExpected Outcomes and Impact.\r\nThe project will (i) reveal population-specific drivers and mutational processes, (ii) quantify the frequency of clinically\r\nactionable biomarkers originally identified in Europeans, (iii) deliver image-based tools that offer low-cost, molecular\r\nstratification and heterogeneity scoring, and (iv) provide a high-resolution evolutionary framework for EO versus LO CRC.\r\nCollectively, these data will offer the first high-resolution portrait of the Chilean CRC and lay the groundwork for\r\nancestry-aware screening, diagnostic, and treatment strategies.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1261473<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2026 - Marzo 2029<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26188\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Geomorphological and ecological dynamics of a deglaciated landscape in the subtropical Andes: The proglacial zone of Universidad Glacier, central Chile (34\u00baS)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26188\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26188\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"].[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> PYT-2026-186<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2026 - Marzo 2029<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Fundaci\u00f3n para la Innovaci\u00f3n Agraria - FIA<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26271\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Obtenci\u00f3n de ingredientes funcionales desde pulpa de sand\u00eda residual post cosecha para su uso en la industria de alimentos funcionales y en la agricultura\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26271\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26271\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La producci\u00f3n de semillas de sand\u00eda en Chile es una de las que genera mayores vol\u00famenes (12,5%) y mejores precios (26 MM U$FOB) de\r\nexportaci\u00f3n respecto del total de semillas exportadas. En los \u00faltimos 5 a\u00f1os su exportaci\u00f3n ha aumentado considerablemente ocupando el\r\nsegundo lugar en este mercado. Derivado del procesamiento de los frutos se genera un alto porcentaje de pulpa y c\u00e1scara; residuos no\r\naprovechables como subproducto para otras industrias como cuarta gama y\/o farmac\u00e9utica. El elevado contenido antioxidantes de la sand\u00eda\r\nrepresenta una oportunidad para su extracci\u00f3n y uso en otras industrias. La soluci\u00f3n innovadora permitir\u00e1 reutilizar grandes vol\u00famenes de la\r\npulpa y c\u00e1scara, mitigando su disposici\u00f3n inadecuada y mejorando pr\u00e1cticas agr\u00edcolas y biotecnol\u00f3gicas. El objetivo de la propuesta es\r\ndesarrollar un paquete tecnol\u00f3gico consistente en tres aplicaciones que permiten valorizar los residuos de c\u00e1scara y pulpa de sand\u00eda para la\r\nproducci\u00f3n de nutrac\u00e9uticos, bioenmienda de suelos provenientes de relaves mineros, y sustrato para el crecimiento de microorganismos. El\r\nproyecto busca generar innovaciones que promuevan la transformaci\u00f3n de los residuos agr\u00edcolas, proyectando as\u00ed nuevos negocios para los\r\nproductores hort\u00edcolas en la industria de los alimentos dando valor agregado a los residuos derivados del procesamiento de semillas. Los\r\nresultados esperados de esta iniciativa son: Portafolio de al menos 2 ingredientes funcionales (Licopeno y Citrulina) desarrollados y\r\ncaracterizados; validaci\u00f3n t\u00e9cnica del ingrediente principal (Licopeno o citrulina) con actividad antioxidante; bioenmienda validada en un\r\nentorno operacional (campo), alcanzando el nivel de madurez tecnol\u00f3gica TRL7; an\u00e1lisis de mercado robusto que incluye un plan de\r\nescalamiento t\u00e9cnico de la bioenmienda; medio de cultivo validado en un entorno operacional (empresas), alcanzando el nivel de madurez\r\ntecnol\u00f3gica TRL7; y an\u00e1lisis de mercado robusto que incluye un plan de escalamiento t\u00e9cnico.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26277\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Pressure and shear shock waves on porous matrices: The erosion mechanism underneath water-dripping-on-stone craters\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26277\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26277\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The phenomenon of a soft liquid drop eroding a hard stone surface over time, immortalized in the ancient proverb \u00abdripping water wears away the stone,\u00bb presents a profound mechanical puzzle. While craters are common imprints of high-energy events, those formed by persistent, low-energy water dripping are exceptional. The impact energy of a single drop is far below the threshold required to plastically deform or fracture the material, yet erosion occurs. This project seeks to answer the fundamental question: How can water erode stone through dripping and create distinctive craters?\r\nWhile recent advancements in drop-impact dynamics have revealed that an impacting drop generates propagating fronts of intense, singular pressure and shear, these theories were developed for ideal, non-porous surfaces and are insufficient to explain the erosion. Our preliminary experimental work\u0097which has successfully reproduced water-dripping craters on gypsum targets while failing to erode non-porous materials\u0097points to a crucial, previously overlooked element: the porous nature of the target material. We discovered that erosion and the formation of a distinct surface microstructure of pores commence only after the substrate becomes fully saturated with water. This key finding suggests that the complex interaction between the impact-induced flow and the internal, liquid-filled pore structure is the primary driver of the erosion mechanism.\r\nThis project will establish the first comprehensive experimental and theoretical framework for slow erosion in porous ma- terials by water dripping. We will investigate three potential and non-exclusive micro-mechanisms. The first is low-Reynolds accumulative erosion, where the impact pressure pumps liquid into the matrix, generating high shear stress along pore walls that slowly abrades material, a process whose rate is expected to be proportional to the wall shear stress. The second is the inter-pore propagation of pressure shocks; because the surface pressure front arrives at adjacent pore openings at slightly different times, large pressure gradients are generated within the saturated matrix, inducing mechanical fatigue and failure of inter-pore walls. The third is cavitation bursts, where the negative-pressure front trailing the initial impact shock\u0097 akin to an explosion\u0092s blast wave\u0097causes the formation and violent collapse of vapor bubbles. These collapses generate localized but highly destructive shock waves, a process potentially detectable via acoustic emissions.\r\nOur methodology integrates a novel, multi-scale experimental approach with robust theoretical modeling. An automated, custom-built setup, featuring a syringe pump for precise drop control and a photo-gate for impact counting and synchroniza- tion, tracks crater evolution over tens of thousands of reproducible impacts. An automated translation stage will move the sample between the impact zone and a characterization chamber for on-the-run 3D shape reconstruction via high-resolution laser profilometry and for mass measurement via an integrated load cell. This will be complemented by a suite of characteriza- tion techniques, including high-speed imaging to capture rare ejecta events, microscopic surface imaging, and advanced bulk imaging (X-ray Micro-Tomography, Scanning Electron Microscopy or Nuclear Magnetic Resonance) to visualize the internal 3D pore network and wear propagation. Experiments will mainly utilize natural materials like gypsum and selenite, as well as custom-fabricated synthetic porous samples (e.g., PDMS). These transparent, engineered samples will allow for direct flow visualization via Particle Image Velocimetry (PIV) to isolate and study specific mechanisms in a controlled environment.\r\nThe theoretical work will couple established models for drop-impact pressure distributions with frameworks for flow in porous media, wall-shear erosion, and wave propagation. The goal is to develop predictive formulae for crater growth rates and their scaling with fluid and material properties, which can be validated against our extensive experimental data. By leveraging the research team\u0092s expertise in drop-impact forces and tackling this 2,500-year-old question, this project will provide novel insights into fluid-solid interactions, wear on porous materials, and landscape evolution. It moves beyond prior studies, which used simplified substrates, to address the central role of porosity in this long-unsolved problem in continuum physics.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2026 - Diciembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26380\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Paquete tecnol\u00f3gico transferible para el control sustentable de nem\u00e1todos gastrointestinales en ovinos Hidango del secano costero de Cardenal Caro\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26380\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26380\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En la Provincia de Cardenal Caro, el control de nem\u00e1todos gastrointestinales (NGI) en ovinos se\r\nrealiza principalmente mediante antiparasitarios qu\u00edmicos, con resultados heterog\u00e9neos entre\r\npredios. Esta variabilidad puede responder a una combinaci\u00f3n de factores: composici\u00f3n local de\r\nespecies parasitarias, fallas de dosificaci\u00f3n\/administraci\u00f3n y\/o presencia de resistencia\r\nantihelm\u00edntica. La ausencia de herramientas diagn\u00f3sticas operativas y de criterios\r\nestandarizados de decisi\u00f3n a nivel predial favorece tratamientos repetidos sin evaluaci\u00f3n\r\nobjetiva de eficacia, elevando costos y aumentando la presi\u00f3n de selecci\u00f3n de resistencia, con\r\npotenciales externalidades ambientales asociadas a residuos en heces.\r\nLa propuesta desarrolla y transfiere un paquete tecnol\u00f3gico de bajo costo y alta aplicabilidad\r\npara el secano costero de Cardenal Caro, utilizando ovinos Hidango como poblaci\u00f3n objetivo. El\r\npaquete se estructura en tres componentes integrados: (1) diagn\u00f3stico aplicado y l\u00ednea base\r\nterritorial, basado en muestreo seriado, recuento de huevos (HPG\/EPG) cuando corresponda y\r\nregistro estandarizado de tratamientos, manejo y condici\u00f3n corporal; (2) confirmaci\u00f3n\r\ntaxon\u00f3mica y validaci\u00f3n molecular estrat\u00e9gica (submuestra sentinela) para respaldar la\r\npertinencia territorial de las recomendaciones sin aumentar costos; y (3) transferencia\r\ntecnol\u00f3gica mediante un protocolo operativo (POE), kit de registros y criterios de decisi\u00f3n que\r\npermitan implementar un manejo racional del control parasitario en predios.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26551\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            1260236_Language and interculturality: An examination of mediated practices in the conceptualization and implementation of interculturality in the Spanish, Ancestral Languages, and English as a foreign language school subjects\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26551\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26551\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The rapid increase in immigration and the presence of different Indigenous peoples in the country have resulted in culturally diverse classrooms in Chile. Cultural differences are significant for communication (Otten & Geppert, 2009) and teaching processes (Liddicoat & Scarino, 2013). Hence, intercultural interactions correspond to embodied culture discourses (Carbaugh, 2017; Shi-xu, 2023), which entail the communication practices that take place at institutional levels (i.e., top-down) and language classrooms (i.e., bottom-up). However, some tensions have been identified in these processes, particularly because they seem to maintain cultural and linguistic hierarchies that do not necessarily promote the social mobility or acceptance of minoritized groups (Flores & Rosa, 2015; Unamuno, 2016; Zavala, 2017). Against this backdrop, discursive practices are at the core of how these raciolinguistic hierarchies are maintained, negotiated, and\/or challenged by educational communities. Consequently, the main objective of this research proposal is to examine how language and interculturality are discursively conceptualized and implemented in culturally diverse Chilean schools, specifically within three language subjects: Spanish, Ancestral Languages, and English as a Foreign Language. This objective is articulated through the following research question: How are language and interculturality discursively conceptualized and implemented in culturally diverse Chilean schools across the subjects of Spanish, Ancestral Languages, and English as a Foreign Language? To address this question, the project outlines four specific objectives (SOs): SO1) To examine how interculturality is discursively constructed in educational policies and the national curriculum on language subjects (i.e., Spanish, Ancestral Languages, and English as a Foreign Language); SO2) To assess how language teachers understand and implement intercultural practices in Chile, highlighting areas of convergence and divergence; SO3) To analyze how school communities discursively construct interculturality on their schoolscapes; and SO4) To analyze how language teachers\u0092 actions and decisions address interculturality in the language classroom.\r\nThe proposed research is a mixed-methods study (Creswell & Plano, 2018). First, we will analyze a corpus of institutional pedagogical discourses to examine how interculturality is discursively constructed in educational policies and the national curriculum (SO1). To this end, the data will be examined from a Corpus-Assisted Approach to Discourse Studies (CADS) (Partington et al., 2013) following the guidelines proposed by Jaworska and Kinloch (2018, p. 116) for a thorough and systematic examination of multiple datasets in CADS. The first quantitative stage considers the analysis of frequency, concordance lines, collocations, and keywords. The second qualitative stage is informed by Bacchi's (2012) model, What's the Problem Represented to be? (or WPR) and the Discourse-Historical Approach (Reisigl, 2017; Reisigl & Wodak, 2016). Second, we will conduct a questionnaire to identify how language teachers understand interculturality and intercultural practices in their classrooms (SO2). The sampling considers a disproportionate stratification to enable similar sample sizes for Spanish and EFL teachers, and Traditional Educators, ensuring the representation of Traditional Educators, who are the smallest population (CEM Mineduc, 2024). Third, we will analyze how school communities discursively construct interculturality on their school grounds (SO3) through the examination of schoolscapes (Gorter & Cenoz, 2015). To this end, three schools across three regions will be selected (i.e., Tarapac\u00e1, Metropolitan, and Araucan\u00eda) to ensure geographic representativeness. The data will be analyzed in light of Ledin and Machin\u0092s multimodality framework (2017, 2018, 2019) as it incorporates the materiality of the semiotic signs, the ideologies and beliefs behind the creation of multimodal texts, and the recontextualization of social actors and practices (van Leeuwen, 2008). Finally, we analyze the actions and decisions language teachers take to address interculturality in the language classroom (SO4) through classroom observation (minimum 48 pedagogical hours in total; four hours per language subject) in the same schools. These observations will be analyzed using the synopsis technique (Dolz et al., 2018; Schneuwly & Dolz, 2009), which allows us to both hierarchize central pedagogical sequences and examine teachers' actions and students' reactions in detail. In turn, it enables data reduction and serves as heuristic support for analysis.\r\nExpected results seek to enlighten how educators co-create language and interculturality in culturally diverse schools. It examines how these social actors recontextualize and mediate top-down policies to their daily realities, thus illuminating the negotiation and resemiotization of hegemonic understandings of interculturality in line with the needs of their own communities (bottom-up practices).[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 3261097<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26552\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Procesos de convivencia intercultural en escuelas secundarias chilenas diversas: un estudio multimodal y decolonial en relaci\u00f3n a los discursos y pr\u00e1cticas escolares sobre la producci\u00f3n de diferencias \u00e9tnicas y migrantes\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26552\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26552\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo general: Examinar los procesos de convivencia intercultural y describir los discursos y pr\u00e1cticas escolares sobre la producci\u00f3n de diferencias \u00e9tnicas y migrantes en dos escuelas secundarias chilenas diversas en la Regi\u00f3n de O'Higgins y en la Regi\u00f3n Atacama.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Patrocinante<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2026 - Marzo 2030<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26606\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Mixed-integer quadratic bilevel optimization algorithms for security and decision-focused learning\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26606\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26606\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Postulaci\u00f3n a Fondecyt Regular[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>INRIA associative teams<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26607\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Reliable Artificial Intelligence via Stochastic Game Techniques\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26607\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26607\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Game theory and artificial intelligence are deeply connected fields, particularly when model-\r\ning adversarial learning problems as Stackelberg games under uncertainty. In such settings,\r\n\r\ndefenders allocate resources randomly to prevent attackers from anticipating their moves. As\r\ntime evolves, the environment changes, and new strategies or actions may emerge. A suitable\r\nsubfield of game theory to model these dynamics is stochastic games, where the state captures\r\n\r\nthe set of available actions in a time-dependent process. Moreover, the attacker\u0096defender inter-\r\naction naturally exhibits a hierarchical bilevel structure: the defender must design randomized\r\n\r\nstrategies to protect targets, while the attacker responds by executing an action that maxi-\r\nmizes its reward. This makes stochastic dynamic Stackelberg games a model of choice for such\r\n\r\napplications [15], the Chilean party being very active in the domain [9, 10, 11].\r\nIn a previous collaboration [1], we have shown that defining an appropriate solution concept\r\nfor these games is far from trivial, and in some cases remains an open research question. Even\r\nwhen a proper solution concept can be established, computing it becomes prohibitively expensive\r\nfor games with massive state and action spaces.\r\nThese challenges are not only of theoretical interest but also of high practical relevance.\r\nThis associate team will focus on two among the many possible applications.\r\nChallenge 1: The first one is wildfire prevention. This theme has been widely examined in\r\nthe literature, particularly through models that optimize the design of firebreaks [16], [12] and\r\nthe the placement of surveillance cameras to limit fire spread. In contrast, the operational\r\n\r\ndimension of prevention and firefighting\u0097where resources must be dynamically allocated un-\r\nder uncertainty\u0097has received far less attention. Emerging distributed AI technologies with\r\n\r\nautonomous agents, both centralized (e.g., coordinated command-and-control systems) and de-\r\ncentralized (e.g., drones and sensor swarms), could play a key role in addressing this challenge.\r\n\r\nChallenge 2: Similarly, in the domain of distributed AI learning systems (e.g. Federated\r\nLearning), a central authority is in charge of agregating the updates of distributed clients in the\r\nprocess of minimizing a global metric. The presence of Byzantine (or faulty) agents can derail\r\nconvergence or induce a biais in this process. To mitigate this, robust agregation techniques\r\nhave been proposed in the literature based on identifying and discarding suspect contributions\r\n[17, 18, 19]. But concrete attacks like ALIE [20] or FoE [21] tend to exhibit patterns. This lead\r\nresearchers to propose the first history-aware defenses [22, 23, 24]. Purely deterministic rules,\r\nthough, are likely to be defeated by powerful and well-informed agents. The attacker\u0096defender\r\nframework is crucial to design secure training environments against adversarial manipulations,\r\nthe principal issue being to decide if and when to exclude a suspected malicious agent.\r\nBoth these applications can be tackeled with tools of Game Theory. More applications\r\ncould be cited, like environmental conservation problems, such as poaching prevention [25],\r\nenvironmental tax evasion [26] or border patrol security [9].[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> PYT-2026-186<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2026 - Marzo 2029<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Fundaci\u00f3n para la Innovaci\u00f3n Agraria - FIA<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26633\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Obtenci\u00f3n de ingredientes funcionales desde pulpa de sand\u00eda residual post cosecha para su uso en la industria de alimentos funcionales y en la agricultura\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26633\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26633\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La producci\u00f3n de semillas de sand\u00eda en Chile es una de las que genera mayores vol\u00famenes (12,5%) y mejores precios (26 MM U$FOB) de\r\nexportaci\u00f3n respecto del total de semillas exportadas. En los \u00faltimos 5 a\u00f1os su exportaci\u00f3n ha aumentado considerablemente ocupando el\r\nsegundo lugar en este mercado. Derivado del procesamiento de los frutos se genera un alto porcentaje de pulpa y c\u00e1scara; residuos no\r\naprovechables como subproducto para otras industrias como cuarta gama y\/o farmac\u00e9utica. El elevado contenido antioxidantes de la sand\u00eda\r\nrepresenta una oportunidad para su extracci\u00f3n y uso en otras industrias. La soluci\u00f3n innovadora permitir\u00e1 reutilizar grandes vol\u00famenes de la\r\npulpa y c\u00e1scara, mitigando su disposici\u00f3n inadecuada y mejorando pr\u00e1cticas agr\u00edcolas y biotecnol\u00f3gicas. El objetivo de la propuesta es\r\ndesarrollar un paquete tecnol\u00f3gico consistente en tres aplicaciones que permiten valorizar los residuos de c\u00e1scara y pulpa de sand\u00eda para la\r\nproducci\u00f3n de nutrac\u00e9uticos, bioenmienda de suelos provenientes de relaves mineros, y sustrato para el crecimiento de microorganismos. El\r\nproyecto busca generar innovaciones que promuevan la transformaci\u00f3n de los residuos agr\u00edcolas, proyectando as\u00ed nuevos negocios para los\r\nproductores hort\u00edcolas en la industria de los alimentos dando valor agregado a los residuos derivados del procesamiento de semillas. Los\r\nresultados esperados de esta iniciativa son: Portafolio de al menos 2 ingredientes funcionales (Licopeno y Citrulina) desarrollados y\r\ncaracterizados; validaci\u00f3n t\u00e9cnica del ingrediente principal (Licopeno o citrulina) con actividad antioxidante; bioenmienda validada en un\r\nentorno operacional (campo), alcanzando el nivel de madurez tecnol\u00f3gica TRL7; an\u00e1lisis de mercado robusto que incluye un plan de\r\nescalamiento t\u00e9cnico de la bioenmienda; medio de cultivo validado en un entorno operacional (empresas), alcanzando el nivel de madurez\r\ntecnol\u00f3gica TRL7; y an\u00e1lisis de mercado robusto que incluye un plan de escalamiento t\u00e9cnico.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1261483<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2026 - Marzo 2030<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26769\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Rethinking police empowerment: unpacking its meaning and consequences\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26769\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26769\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]In this project, police empowerment is preliminarily defined as the process by which police forces are\r\ngranted powers or see their existing powers expanded through legal mandates (e.g., laws that grant police\r\nforces with more attributions or discretion), institutional and administrative capacities (e.g., budget\r\nincrease), and social perceptions (e.g., citizens\u0092 and authorities\u0092 perceptions and support for police\r\nempowerment, as well as police officers\u0092 self-empowerment). Existing research has largely focused on\r\nisolated dimensions of this process\u0097either legal, institutional, or perceptual\u0097but has not addressed how\r\nthese interact or differ in their consequences. This project addresses this gap by (a) proposing a\r\nmultidimensional, contextually grounded, conceptual and operational definition of police empowerment and\r\nanalyzing how its different components\u0097moderated by accountability\u0097affect public security and order,\r\nand the potential for police abuse.\r\nTo achieve these goals, we adopt a multi-method design composed of six interrelated studies. These\r\ninclude expert interviews (Study 1), a longitudinal panel survey with citizens (EPSEP, Study 2), secondary\r\ndata analysis (legal, institutional\/administrative and authorities\u0092 discourse analysis, Study 3), interviews with\r\npolice officers (Study 4), a quasi-experimental study of the effect of key moments of empowerment (e.g.,\r\nthe enactment of a new law increasing police power, Study 5) on the aforementioned consequences, and\r\nan experimental study with police personnel (Study 6). Study 2 will also enable longitudinal, quasi-\r\nexperimental (via a rolling cross-sectional design), and experimental analyses of the effects of police\r\nempowerment among citizens.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26779\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Evaluation of microplastic pollution on soil microbiota, biogeochemistry, and crop health in agricultural systems\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26779\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26779\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]o assess microplastic pollution in agricultural soils in the O'Higgins Region and its impact on biogeochemical cycles, soil microbiota, and the eco-physiological and agronomic response of agricultural plants.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Patrocinante<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1260786<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2026 - Marzo 2030<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26930\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Advanced Tactile Robotics Technologies for Studying the Neuroscience of Social Touch and Enhancing Human-Robot Communication\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26930\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26930\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]-[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2026 - Marzo 2029<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26966\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Effects of increased waterlogging under climate change on avocados (Persea americana Mill cv. Hass) grafted to several rootstocks\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26966\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26966\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Avocado is a very nutritious and tasty fruit, characteristics that have caused a high global demand for this fruit. Increasing evidence of health benefits of the avocado is both driving increased consumption and stimulating research. Over the next few decades, a number of climate-related factors are expected to undergo significant change, leading to increases in CO2 and, depending on the region, temperature, humidity, salinity, flooding, and drought. Chile is expected to experience more frequent and severe flooding in the future due to climate change and sea level rise. By 2050, flooding in Chile could increase by an order of magnitude compared to the previous decade, while by the end of the century, Chile could experience more than 100 days of flooding each year. The frequency and severity of flooding will increase as sea levels rise. Under such predicted conditions, avocado orchards will suffer significant harm from waterlogging, which significantly will affect the growth, physiological performance and a general avocado production.\r\nThe majority of avocado orchards are currently vulnerable to sporadic waterlogging as a result of climate change, either because of poor soil qualities or occasionally rising water tables. Waterlogging detrimentally affects avocado orchards at various levels. Reduced root and shoot growth due to soil oxygen depletion (plant-soil system), decreased transpiration rate, changes in the soil's oxidation-reduction status, decreased redox potential and ultimately decreased avocado production are the main effects of waterlogging on avocado. Climate change is increasing the frequency and severity of extreme weather events with flooding being the largest concern for Chile.  Investigating how climate change factors combine with waterlogging stress, novel genes, and signaling components can provide useful insights into plant responses to waterlogging stress and future agricultural difficulties\r\n \r\nThe species and occasionally the cultivar determine how long a plant may survive in a waterlogged condition. The rootstock (clonal or seedling rootstocks) used in the orchard may have an impact on the sensitivity to waterlogging. In this Project, it was hypothesized that: (1) Hass avocado grafted to different rootstocks (clonal or from seedling) may have a differential performance under waterlogging conditions and that the tolerance is driven by rootstock cultivar, stress severity, balance of oxidative stress and defense system at morpho-physiological, biochemical and molecular level and (2): Clonal o seedling rootstock  influence Hass avocado responses to waterlogging by affecting root microbial community, carbon, nitrogen cycling and reduced soil components. Thus, the main objective of this proposal is to evaluate the effects of waterlogging on grafted Hass avocado to 04 different rootstocks (Dusa, Duke 7, Mexicola and Zutano) mainly used in the Central and South-Central region of Chile. \r\n \r\nA systematic fingerprinting analysis will be used in this project by integrating different tools for deep analysis (Chemo-Metabolomics, transcriptomics and metagenomics) and for monitoring changes in morpho-physiological and gas-exchange parameters, changes in plant-soil system by evaluating the composition and function of microbial communities within the pot soil in each treatment, the antioxidant defense system and reactive oxygen species, for better understanding the regulatory mechanisms of tolerance to waterlogging, identification of the potential genes regulating tolerance to waterlogging in Hass avocado and finally the selection of the rootstock with better agronomic performance. Four (4) different rootstocks will be used in this research (two hybrids from Mexican and Guatemalan races - Zutano and Dusa, two Mexican races - Mexicola and Duke 7) which will be grafted with the scion material collected from Hass avocado cultivar. Mexicola and Zutano Will be propagated by seeds; Duke 7 clonally propagated and clonal Dusa plantlets acquired in the national plant propagation nurseries due to protection of intellectual property. One year grafted Hass avocado on different rootstocks will be subjected to a waterlogging greenhouse experiment by submerging them in a plastic water tank with water level 5 cm above the soil Surface (140% field capacity) for 3, 6, 9, and 15 days against the control treatment (no waterlogging stress). Morphological, physio-biochemical and gas-exchange parameters, soil nutrient dinamics, function and composition of microbial community within the pot soil and sampling for transcriptomic analysis will then be performed.\r\n \r\nThe results of this study are expected not only to provide more foundation into the agronomic, biochemical and molecular aspects associated to waterlogging of \u0091Hass\u0092 avocados grafted on different rootstocks but also provide potential biomarkers and genes involved in stress tolerance and select the best suited rootstocks for the current and the upcoming extreme climate change events, which may help to implement new Hass avocado production protocols that will reduce this predicted climate change problem in practice. This project will generate scientific and academic publications, extension and training of young researchers and will strengthen the network with national and international key partners. The findings will be also valuable for agronomists, plant physiologists, microbiologists and plant breeders to develop new avocado production protocols useful for waterlogging conditions that are predicted in Chile.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2026 - Marzo 2029<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26967\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26967\" aria-expanded=\"false\" aria-controls=\"collapse-26967\">\n                                            Effects of increased waterlogging under climate change on avocados (Persea americana Mill cv. Hass) grafted to several rootstocks\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26967\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26967\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Avocado is a very nutritious and tasty fruit, characteristics that have caused a high global demand for this fruit. Increasing evidence of health benefits of the avocado is both driving increased consumption and stimulating research. The results of this study are expected not only to provide more foundation into the agronomic, biochemical and molecular aspects associated to waterlogging of \u0091Hass\u0092 avocados grafted on different rootstocks but also provide potential biomarkers and genes involved in stress tolerance and select the best suited rootstocks for the current and the upcoming extreme climate change events, which may help to implement new Hass avocado production protocols that will reduce this predicted climate change problem in practice.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> Fondecyt Regular 1261710<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26982\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Noticing para la equidad y conocimiento para la ense\u00f1anza de las matem\u00e1ticas: construyendo aulas de matem\u00e1ticas inclusivas a trav\u00e9s del desarrollo profesional de profesores de educaci\u00f3n especial\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26982\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26982\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La formaci\u00f3n de los profesores de educaci\u00f3n especial ha transitado desde un modelo cl\u00ednico, centrado en el d\u00e9ficit, hacia un modelo socioeducativo que se centra en la inclusi\u00f3n del estudiante, atendiendo sus necesidades y reconociendo sus derechos (Tenorio et al., en prensa), lo que les permite atender a la diversidad m\u00e1s all\u00e1 del d\u00e9ficit. No obstante, dicha mirada no siempre se refleja en la ense\u00f1anza de las matem\u00e1ticas. Por ejemplo, estudios recientes revelan que los profesores de educaci\u00f3n especial tienden a priorizar una ense\u00f1anza funcional de las matem\u00e1ticas \u0097como el manejo del dinero o actividades pr\u00e1cticas\u0097 con el fin de fomentar la autonom\u00eda y la inclusi\u00f3n laboral de estudiantes con discapacidad intelectual (San Martin et al., 2025). Si bien este enfoque puede ser valioso, centrar la ense\u00f1anza \u00fanicamente en lo funcional limita el acceso al desarrollo del pensamiento matem\u00e1tico, considerado un objetivo central del curr\u00edculo escolar (e.g., Schoenfeld, 2022), y puede traducirse en una forma de exclusi\u00f3n que ha sido calificada como deshumanizante (Tan et al., 2020). Esto se debe a que, bajo el argumento de unas matem\u00e1ticas funcionales, se recorta el curr\u00edculo a estudiantes que presentan discapacidad o alguna barrera para el aprendizaje (Greenstein & Baglieri, 2018). Esta tendencia se ve reforzada por el predominio de la instrucci\u00f3n directa en la educaci\u00f3n especial, que reduce las matem\u00e1ticas a una secuencia de procedimientos por repetir (e.g., Gersten et al., 2009; Montague & Jitendra, 2012; Schnepel & Aunio, 2021), privando a los estudiantes de oportunidades para ejercer su capacidad de pensar y participar activamente en la construcci\u00f3n de significado (Lambert, 2018; Tan et al., 2020).\r\n\r\nEn este contexto, este proyecto apunta a dos factores que podr\u00edan apoyar la superaci\u00f3n de esta problem\u00e1tica: (a) el conocimiento matem\u00e1tico para la ense\u00f1anza de profesores de educaci\u00f3n especial y (b) el uso de este conocimiento en tareas situadas, como atender al pensamiento matem\u00e1tico de los estudiantes. Para abordar este prop\u00f3sito, nos apoyamos en el conocimiento profesional para ense\u00f1ar matem\u00e1ticas, entendido en este trabajo a partir de tres constructos te\u00f3ricos: (a) el conocimiento para la ense\u00f1anza de las matem\u00e1ticas, desde dos perspectivas diferentes y complementarias \u0097el Political Conocimiento for Teaching Mathematics (PCTM; Guti\u00e9rrez, 2012, 2017) y el Mathematics Teacher Specialised Knowledge (MTSK; Carrillo et al., 2018)\u0097, y (b) el noticing multidimensional para la equidad (van Es & Sherin, 2021, 2022).\r\n\r\nLa racionalidad de esta decisi\u00f3n radica en que los diversos modelos sobre el conocimiento del profesorado han evidenciado la complejidad de la relaci\u00f3n entre el conocimiento matem\u00e1tico y su despliegue en las distintas pr\u00e1cticas que configuran la ense\u00f1anza de esta disciplina (Llinares, 2019). En este sentido, la investigaci\u00f3n en torno al conocimiento del profesor de matem\u00e1ticas se ha desarrollado principalmente desde dos enfoques (Depaepe et al., 2013; Kaiser et al., 2017): por un lado, una perspectiva cognitiva, que ha dado lugar a marcos te\u00f3ricos que distinguen anal\u00edticamente distintas facetas del conocimiento; y, por otro, una perspectiva situada, que concibe el conocimiento docente como din\u00e1mico, emergente de la pr\u00e1ctica y movilizado a trav\u00e9s de la reflexi\u00f3n y la interacci\u00f3n en el aula. En este proyecto optamos por integrar ambas perspectivas, ya que, por una parte, est\u00e1n respaldadas te\u00f3rica y emp\u00edricamente (Cenigz et al., 2011; Thomas et al., 2017) y, por otra, su articulaci\u00f3n permite avanzar hacia una comprensi\u00f3n m\u00e1s hol\u00edstica del conocimiento profesional del profesorado que ense\u00f1a matem\u00e1ticas (Kaiser et al., 2014; Santagata & Yeh, 2016; Stahnke et al., 2016).\r\n\r\nDesde este marco, nos planteamos dos preguntas de investigaci\u00f3n: \u00bfc\u00f3mo se desarrolla el PCTM y el MTSK de los profesores de educaci\u00f3n especial?, y \u00bfc\u00f3mo se desarrolla el noticing multidimensional para la equidad en estos profesores? Estas preguntas se concretizan en el siguiente objetivo general: caracterizar el proceso de desarrollo del conocimiento profesional para ense\u00f1ar matem\u00e1ticas del profesorado de educaci\u00f3n especial durante un curso de formaci\u00f3n continua.\r\n\r\nPara el logro de este objetivo se ha dise\u00f1ado una investigaci\u00f3n basada en el dise\u00f1o (Cobb et al., 2016; Molina et al., 2011). De manera general, este dise\u00f1o contempla un primer a\u00f1o destinado a la revisi\u00f3n de la literatura, el dise\u00f1o general del curso y de las entrevistas, la formaci\u00f3n del facilitador y una primera recogida de datos mediante entrevistas. La implementaci\u00f3n del curso de desarrollo profesional se realizar\u00e1 principalmente durante el segundo y tercer a\u00f1o. En el segundo a\u00f1o, el foco estar\u00e1 puesto en el desarrollo del PCTM y el MTSK mediante dos sesiones mensuales durante diez meses. Al finalizar este periodo, se repetir\u00e1n las entrevistas personales con los participantes, ahora centradas en el desarrollo del PCTM y el MTSK. Durante el tercer a\u00f1o, el proyecto contempla la implementaci\u00f3n de un club de video que seguir\u00e1 el formato propuesto por van Es y Sherin (2008). Concretamente, se realizar\u00e1n diez reuniones mensuales en las que se reflexionar\u00e1 en torno al marco del noticing multidimensional para la equidad (van Es & Sherin, 2022). Finalmente, durante el cuarto a\u00f1o, se realizar\u00e1 una tercera recogida de datos mediante entrevistas orientadas a indagar tanto el desarrollo del noticing como el uso de los modelos PCTM y MTSK. Estas entrevistas permitir\u00e1n dar cuenta del proceso completo y ser\u00e1n analizadas en contraste con las dos recogidas previas.\r\n\r\nEn este curso de desarrollo profesional participar\u00e1n profesores de educaci\u00f3n especial que se desempe\u00f1en actualmente en cursos de 1.\u00ba a 6.\u00ba b\u00e1sico, provenientes de cuatro contextos escolares en los que se despliega la educaci\u00f3n especial: (a) escuelas para estudiantes sordos, (b) escuelas para estudiantes ciegos, (c) escuelas para estudiantes con TEA y (d) escuelas regulares con Programa de Integraci\u00f3n Escolar (PIE).\r\n\r\nLos resultados esperables de este proyecto permitir\u00e1n identificar \u00e1reas de conocimiento cr\u00edtico que los profesores de educaci\u00f3n especial necesitan para desempe\u00f1ar con \u00e9xito la docencia en matem\u00e1ticas. En este sentido, los hallazgos podr\u00e1n orientar ajustes o propuestas para los programas de formaci\u00f3n inicial docente, focalizando en aquellos aspectos que, tanto la literatura como los propios profesores en servicio, consideran necesarios para su desempe\u00f1o profesional.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2026 - Marzo 2029<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27018\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27018\" aria-expanded=\"false\" aria-controls=\"collapse-27018\">\n                                            Effects of increased waterlogging under climate change on avocados (Persea americana Mill cv. Hass) grafted to several rootstocks\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27018\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27018\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Avocado is a very nutritious and tasty fruit, characteristics that have caused a high global demand for this fruit. Increasing evidence of health benefits of the avocado is both driving increased consumption and stimulating research. The results of this study are expected not only to provide more foundation into the agronomic, biochemical and molecular aspects associated to waterlogging of \u0091Hass\u0092 avocados grafted on different rootstocks but also provide potential biomarkers and genes involved in stress tolerance and select the best suited rootstocks for the current and the upcoming extreme climate change events, which may help to implement new Hass avocado production protocols that will reduce this predicted climate change problem in practice.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11261116<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2026 - Marzo 2029<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27064\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Cooperative control of intelligent agents using reinforcement learning to support the implementation of AC\/DC multi-microgrids in the energy industry, from regions in Chile to the rest of the world.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27064\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27064\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]This project will address the implementation of distributed controllers in intelligent agents within AC\/DC electrical microgrids. Specifically, this project will address open issues in the distributed control literature for microgrids; these include optimal \r\nparameter tuning and resilience to communications disturbances such as transport delays, packet loss, and communication failures due to cyberattacks. All of these are important components that prevent the proliferation of microgrid projects throughout the country and the world. Microgrids have the potential to improve the energy management of renewable resources and the resilience of current and future electrical systems. Furthermore, they aid in decarbonization and benefit the energization of isolated communities and national industries. Based on the above, the main objective of this research is to formulate, implement, and validate distributed intelligent controllers, using reinforcement learning, in agents that comprise interconnected AC\/DC microgrids, in order to achieve optimal operation concerning available energy resources despite disturbances and failures in communication channels. To achieve this objective, the following specific objectives are specified: (i) investigate the state of the art in the use of reinforcement learning algorithms in cooperative multi-agent system control and their application to microgrids; (ii) design a deep reinforcement learning algorithm to auxiliary control an ILC of a hybrid AC\/DC microgrid with communication loss and variable time delays; (iii) design a distributed controller with parameter and structure adjustment capability through deep reinforcement learning algorithms for the agents of an AC\/DC multi-microgrid with communication losses and variable time delay; (iv) design a robust distributed controller through deep reinforcement learning algorithms that allows agents in an AC\/DC multi-microgrid to be resilient to heterogeneous and variable transport delays, loss of data packets, and DoS cyber-attacks; (v) build a prototyping platform for multi-agent-based intelligent agent control schemes with digital twin co-simulation; (vi) implement and validate the proposed reinforcement learning controllers in an AC\/DC multi-microgrid experimental setup.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 3261097<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27078\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Procesos de convivencia intercultural en escuelas secundarias chilenas diversas: un estudio multimodal y decolonial en relaci\u00f3n a los discursos y pr\u00e1cticas escolares sobre la producci\u00f3n de diferencias \u00e9tnicas y migrantes\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27078\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27078\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo general: Examinar los procesos de convivencia intercultural y describir los discursos y pr\u00e1cticas escolares sobre la producci\u00f3n de diferencias \u00e9tnicas y migrantes en dos escuelas secundarias chilenas diversas en la Regi\u00f3n de O'Higgins y en la Regi\u00f3n Atacama.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11260818<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2026 - Marzo 2029<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27126\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Una Etnograf\u00eda Institucional del Agua Potable Rural y Saneamiento: hacia una gesti\u00f3n intercultural\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27126\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27126\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto analiza c\u00f3mo se organiza material y discursivamente el Programa de Agua Potable Rural y Saneamiento (APR) en Chile para contribuir a una gesti\u00f3n intercultural del agua potable rural y saneamiento desde cuatro proyectos situados en comunidades mapuche en la regi\u00f3n de La Araucan\u00eda.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2026 - Marzo 2029<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26378\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Searching for the Southern boundary of triatomine occurrence in Chile: An interdisciplinary approach to detect and prevent Chagas disease\u0094,\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26378\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26378\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetivo principal de este proyecto es actualizar y profundizar el conocimiento sobre la distribuci\u00f3n y prevalencia de triatominos vectores de Trypanosoma cruzi en la Regi\u00f3n de O\u0092Higgins, Chile. Esto se realizar\u00e1 a trav\u00e9s del an\u00e1lisis de datos hist\u00f3ricos y actuales de entidades de salud, complementado con muestreos intensivos de mam\u00edferos silvestres y monitoreo de animales dom\u00e9sticos en \u00e1reas identificadas como de alto riesgo. Se explorar\u00e1n adem\u00e1s los focos hist\u00f3ricos y zonas predichas como aptas para la presencia de triatominos, utilizando avanzadas t\u00e9cnicas de detecci\u00f3n molecular y an\u00e1lisis de modelaci\u00f3n. Este estudio busca no solo llenar un vac\u00edo de conocimiento sobre la presencia de estos vectores, sino tambi\u00e9n evaluar c\u00f3mo los cambios clim\u00e1ticos y antr\u00f3picos podr\u00edan estar alterando su distribuci\u00f3n geogr\u00e1fica, afectando as\u00ed el riesgo de transmisi\u00f3n de la enfermedad de Chagas en la regi\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FONDART Nacional de Investigaci\u00f3n 815489<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2026 - Mayo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Fondart Nacional de Investigaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26084\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fondart Investigaci\u00f3n: Pr\u00e1cticas art\u00edsticas colaborativas desde la escuela: aportes y desaf\u00edos para expandir las artes en el territorio\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26084\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26084\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto analizar\u00e1 las dimensiones del arte colaborativo en escuelas de la regi\u00f3n de O`Higgins y Metropolitana[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FONDECYT Regular 1260171<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2026 - Marzo 2029<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26085\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fondecyt Regular: Pr\u00e1cticas art\u00edsticas de mediaci\u00f3n expandida desde contextos educativos: Oportunidades y desaf\u00edos para ampliar el rol social de las artes en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26085\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26085\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Esta investigaci\u00f3n busca conocer las formas en que las escuelas se pueden desempe\u00f1ar como espacios culturales en sus comunidades locales, para lo cual se analizar\u00e1n c\u00f3mo las pr\u00e1cticas art\u00edsticas de mediaci\u00f3n expandida se muestr\u00e1n como una herramienta y metodolog\u00eda id\u00f3nea para su desarrollo e impacto local.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 40074458-0<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2026 - Marzo 2028<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26153\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Rutas de turismo paleoarqueol\u00f3gicas para la Regi\u00f3n de O`higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26153\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26153\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Implementaci\u00f3n de una ruta de turismo arqueol\u00f3gica y paleontol\u00f3gica que abarque tres comunas: San Vicente de Tagua Tagua, Navidad y San Fernando.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26187\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estudio de intrusiones marinas en la costa de la Regi\u00f3n de O\u0092Higgins mediante reflectometr\u00eda interferom\u00e9trica con GNSS\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26187\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26187\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El presente proyecto propone estudiar las intrusiones de agua marina (SWI, por sus siglas en ingl\u00e9s) en la\r\nlocalidad costera de Bucalemu, comuna de Paredones, Regi\u00f3n de O\u0092Higgins, con el objetivo de entender c\u00f3mo\r\nlas variaciones del nivel del mar y la llegada de R\u00edos Atmosf\u00e9ricos afectan la salinidad de suelos y cuerpos de\r\nagua costeros. Las SWIs constituyen un fen\u00f3meno en aumento debido al cambio clim\u00e1tico y al alza sostenida\r\ndel nivel medio del mar, lo que impacta negativamente los recursos h\u00eddricos, la calidad del suelo y la\r\nproductividad agr\u00edcola.\r\nEl proyecto surge como una extensi\u00f3n del trabajo previo realizado en Pichilemu por la Universidad de\r\nO\u0092Higgins (proyecto URO RED21992), donde se evidenci\u00f3 un incremento en la conductividad el\u00e9ctrica del\r\nsuelo y la salinidad del estero San Antonio, asociados a eventos de lluvias intensas y marejadas vinculadas a\r\nR\u00edos Atmosf\u00e9ricos. Bucalemu, adem\u00e1s de su importancia tur\u00edstica y pesquera, enfrenta presiones sobre su\r\nacu\u00edfero, declarado en restricci\u00f3n por el Ministerio de Obras P\u00fablicas, lo que refuerza la necesidad de un\r\nmonitoreo cient\u00edfico del fen\u00f3meno.\r\nDesde una perspectiva interdisciplinaria, la investigaci\u00f3n combina la geof\u00edsica, la edafolog\u00eda y la hidrogeolog\u00eda.\r\nLa geof\u00edsica permitir\u00e1 registrar las variaciones del nivel del mar y del estero mediante la t\u00e9cnica de\r\nreflectometr\u00eda interferom\u00e9trica GNSS (GNSS-IR), una metodolog\u00eda innovadora y costo-efectiva que usa\r\nse\u00f1ales satelitales para medir cambios de altura en cuerpos de agua. La edafolog\u00eda abordar\u00e1 los impactos de\r\nla salinidad en el suelo mediante muestreos sistem\u00e1ticos a diferentes profundidades, mientras que la\r\nhidrogeolog\u00eda contribuir\u00e1 a interpretar los procesos de mezcla entre agua dulce y salada.\r\nLas hip\u00f3tesis de trabajo plantean que las variaciones de marea y los R\u00edos Atmosf\u00e9ricos generan incrementos\r\nde la conductividad el\u00e9ctrica del suelo cerca de la desembocadura del estero, y que el impacto de las SWIs\r\ndisminuye tierra adentro. Los objetivos espec\u00edficos incluyen medir simult\u00e1neamente niveles de mar y agua,\r\nidentificar y caracterizar R\u00edos Atmosf\u00e9ricos, analizar su relaci\u00f3n con la salinidad del suelo, y realizar seminarios\r\nde difusi\u00f3n cient\u00edfica en la comunidad.\r\nLa metodolog\u00eda contempla la instalaci\u00f3n de dos estaciones GNSS y un sensor de conductividad el\u00e9ctrica Teros-\r\n12, junto a campa\u00f1as de muestreo de suelo en invierno y verano. Los datos se complementar\u00e1n con an\u00e1lisis\r\nde series temporales y cat\u00e1logos de R\u00edos Atmosf\u00e9ricos derivados del rean\u00e1lisis ERA5. Asimismo, se realizar\u00e1n\r\nvuelos con dron para obtener modelos de elevaci\u00f3n de alta precisi\u00f3n y determinar \u00e1reas vulnerables a\r\ninundaci\u00f3n marina.\r\nEl equipo de trabajo est\u00e1 liderado por el Dr. Ra\u00fal Valenzuela, experto en R\u00edos Atmosf\u00e9ricos y mediciones GNSS,\r\njunto a la Dra. Claudia Rojas, especialista en edafolog\u00eda, y el Dr. Etienne Bresciani, con experiencia en\r\nhidrogeolog\u00eda costera. La colaboraci\u00f3n internacional incluye al Dr. Pierre Bosser (ENSTA Bretagne, Francia),\r\nexperto en GNSS-IR.\r\nEl proyecto contribuir\u00e1 al manejo h\u00eddrico sostenible y la adaptaci\u00f3n al cambio clim\u00e1tico en la Regi\u00f3n de\r\nO\u0092Higgins, fortaleciendo el conocimiento cient\u00edfico y la resiliencia costera mediante una aproximaci\u00f3n\r\ninterdisciplinaria. Se espera que sus resultados sirvan como base para pol\u00edticas p\u00fablicas orientadas a la gesti\u00f3n\r\ndel borde costero y la protecci\u00f3n de ecosistemas como el Humedal de Bucalemu.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26231\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            From Physics to Agricultural Practice: The impact of raindrops on Pseudomonas syringae pv syringae inoculated on sweet cherry leaves\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26231\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26231\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]We investigate how rain-mediated mechanical processes influence the spread of pathogens under field conditions. While it is well established that water is a primary vector for bacterial movement between plants, few studies have examined the detailed hydrodynamic mechanisms involved, particularly in the context of leaf morphology, surface roughness, and microbial adhesion. This gap restricts our ability to develop predictive models and preventive strategies for managing rain-borne plant diseases.\r\nThe project's general objective is to elucidate the coupling between raindrop impact dynamics and bacterial dispersal patterns on cherry leaves under realistic rainfall conditions. Specifically, it aims to (i) characterize the mechanical interaction between raindrops and cherry leaves using high-speed imaging and physical analysis to observe the dispersal patterns of Pseudomonas syringae pv. syringae (Pss). (ii) evaluate the spatial dispersal of Pss inoculated artificially onto cherry leaves at different concentrations under controlled temperature and rainfall conditions, and (iii) develop an integrative predictive model based on physical variables of rain-leaf interaction and experimentally measured environmental conditions to estimate the dispersal and severity of Pss attack.\r\nMethodologically, our study combines high-speed photography, controlled laboratory rain simulations, and microbiological assays. We will perform experiments in a custom-designed rainfall simulator allowing precise control of droplet size, velocity, and impact angle. Bacterial suspensions of Pseudomonas syringae\u0097a pathogen commonly associated with cherry canker\u0097will be applied to leaves under standardized conditions. The dynamics of droplet impact, splash formation, and secondary droplet ejection will be recorded at high temporal resolution to quantify mechanical energy transfer and spatial distribution of splashed particles. Parallel microbiological analyses will determine bacterial survival rates, concentration profiles, and the extent of leaf-to-leaf contamination. We will integrate these results into a predictive model linking rainfall characteristics to potential bacterial dispersal distances and infection probabilities.\r\nWe aim to enhance our understanding of the biophysical coupling between rainfall and pathogen mobility, establish a set of empirical relationships for disease spread modeling, and provide practical recommendations for orchard management under varying climatic scenarios. By bridging the gap between plant pathology and fluid mechanics, this project will provide a mechanistic foundation for reducing rain-mediated bacterial diseases in high-value fruit crops, contributing to the sustainability and resilience of O'Higgins agriculture.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26278\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            From Physics to Agricultural Practice: The impact of raindrops on Pseudomonas syringae pv syringae inoculated on sweet cherry leaves\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26278\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26278\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]We investigate how rain-mediated mechanical processes influence the spread of pathogens under field conditions. While it is well established that water is a primary vector for bacterial movement between plants, few studies have examined the detailed hydrodynamic mechanisms involved, particularly in the context of leaf morphology, surface roughness, and microbial adhesion. This gap restricts our ability to develop predictive models and preventive strategies for managing rain-borne plant diseases.\r\nThe project's general objective is to elucidate the coupling between raindrop impact dynamics and bacterial dispersal patterns on cherry leaves under realistic rainfall conditions. Specifically, it aims to (i) characterize the mechanical interaction between raindrops and cherry leaves using high-speed imaging and physical analysis to observe the dispersal patterns of Pseudomonas syringae pv. syringae (Pss). (ii) evaluate the spatial dispersal of Pss inoculated artificially onto cherry leaves at different concentrations under controlled temperature and rainfall conditions, and (iii) develop an integrative predictive model based on physical variables of rain-leaf interaction and experimentally measured environmental conditions to estimate the dispersal and severity of Pss attack.\r\nMethodologically, our study combines high-speed photography, controlled laboratory rain simulations, and microbiological assays. We will perform experiments in a custom-designed rainfall simulator allowing precise control of droplet size, velocity, and impact angle. Bacterial suspensions of Pseudomonas syringae\u0097a pathogen commonly associated with cherry canker\u0097will be applied to leaves under standardized conditions. The dynamics of droplet impact, splash formation, and secondary droplet ejection will be recorded at high temporal resolution to quantify mechanical energy transfer and spatial distribution of splashed particles. Parallel microbiological analyses will determine bacterial survival rates, concentration profiles, and the extent of leaf-to-leaf contamination. We will integrate these results into a predictive model linking rainfall characteristics to potential bacterial dispersal distances and infection probabilities.\r\nWe aim to enhance our understanding of the biophysical coupling between rainfall and pathogen mobility, establish a set of empirical relationships for disease spread modeling, and provide practical recommendations for orchard management under varying climatic scenarios. By bridging the gap between plant pathology and fluid mechanics, this project will provide a mechanistic foundation for reducing rain-mediated bacterial diseases in high-value fruit crops, contributing to the sustainability and resilience of O'Higgins agriculture.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26326\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estudio de intrusiones marinas en la costa de la Regi\u00f3n de O\u0092Higgins mediante reflectometr\u00eda interferom\u00e9trica con GNSS\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26326\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26326\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El presente proyecto propone estudiar las intrusiones de agua marina (SWI, por sus siglas en ingl\u00e9s) en la\r\nlocalidad costera de Bucalemu, comuna de Paredones, Regi\u00f3n de O\u0092Higgins, con el objetivo de entender c\u00f3mo\r\nlas variaciones del nivel del mar y la llegada de R\u00edos Atmosf\u00e9ricos afectan la salinidad de suelos y cuerpos de\r\nagua costeros. Las SWIs constituyen un fen\u00f3meno en aumento debido al cambio clim\u00e1tico y al alza sostenida\r\ndel nivel medio del mar, lo que impacta negativamente los recursos h\u00eddricos, la calidad del suelo y la\r\nproductividad agr\u00edcola.\r\nEl proyecto surge como una extensi\u00f3n del trabajo previo realizado en Pichilemu por la Universidad de\r\nO\u0092Higgins (proyecto URO RED21992), donde se evidenci\u00f3 un incremento en la conductividad el\u00e9ctrica del\r\nsuelo y la salinidad del estero San Antonio, asociados a eventos de lluvias intensas y marejadas vinculadas a\r\nR\u00edos Atmosf\u00e9ricos. Bucalemu, adem\u00e1s de su importancia tur\u00edstica y pesquera, enfrenta presiones sobre su\r\nacu\u00edfero, declarado en restricci\u00f3n por el Ministerio de Obras P\u00fablicas, lo que refuerza la necesidad de un\r\nmonitoreo cient\u00edfico del fen\u00f3meno.\r\nDesde una perspectiva interdisciplinaria, la investigaci\u00f3n combina la geof\u00edsica, la edafolog\u00eda y la hidrogeolog\u00eda.\r\nLa geof\u00edsica permitir\u00e1 registrar las variaciones del nivel del mar y del estero mediante la t\u00e9cnica de\r\nreflectometr\u00eda interferom\u00e9trica GNSS (GNSS-IR), una metodolog\u00eda innovadora y costo-efectiva que usa\r\nse\u00f1ales satelitales para medir cambios de altura en cuerpos de agua. La edafolog\u00eda abordar\u00e1 los impactos de\r\nla salinidad en el suelo mediante muestreos sistem\u00e1ticos a diferentes profundidades, mientras que la\r\nhidrogeolog\u00eda contribuir\u00e1 a interpretar los procesos de mezcla entre agua dulce y salada.\r\nLas hip\u00f3tesis de trabajo plantean que las variaciones de marea y los R\u00edos Atmosf\u00e9ricos generan incrementos\r\nde la conductividad el\u00e9ctrica del suelo cerca de la desembocadura del estero, y que el impacto de las SWIs\r\ndisminuye tierra adentro. Los objetivos espec\u00edficos incluyen medir simult\u00e1neamente niveles de mar y agua,\r\nidentificar y caracterizar R\u00edos Atmosf\u00e9ricos, analizar su relaci\u00f3n con la salinidad del suelo, y realizar seminarios\r\nde difusi\u00f3n cient\u00edfica en la comunidad.\r\nLa metodolog\u00eda contempla la instalaci\u00f3n de dos estaciones GNSS y un sensor de conductividad el\u00e9ctrica Teros-\r\n12, junto a campa\u00f1as de muestreo de suelo en invierno y verano. Los datos se complementar\u00e1n con an\u00e1lisis\r\nde series temporales y cat\u00e1logos de R\u00edos Atmosf\u00e9ricos derivados del rean\u00e1lisis ERA5. Asimismo, se realizar\u00e1n\r\nvuelos con dron para obtener modelos de elevaci\u00f3n de alta precisi\u00f3n y determinar \u00e1reas vulnerables a\r\ninundaci\u00f3n marina.\r\nEl equipo de trabajo est\u00e1 liderado por el Dr. Ra\u00fal Valenzuela, experto en R\u00edos Atmosf\u00e9ricos y mediciones GNSS,\r\njunto a la Dra. Claudia Rojas, especialista en edafolog\u00eda, y el Dr. Etienne Bresciani, con experiencia en\r\nhidrogeolog\u00eda costera. La colaboraci\u00f3n internacional incluye al Dr. Pierre Bosser (ENSTA Bretagne, Francia),\r\nexperto en GNSS-IR.\r\nEl proyecto contribuir\u00e1 al manejo h\u00eddrico sostenible y la adaptaci\u00f3n al cambio clim\u00e1tico en la Regi\u00f3n de\r\nO\u0092Higgins, fortaleciendo el conocimiento cient\u00edfico y la resiliencia costera mediante una aproximaci\u00f3n\r\ninterdisciplinaria. Se espera que sus resultados sirvan como base para pol\u00edticas p\u00fablicas orientadas a la gesti\u00f3n\r\ndel borde costero y la protecci\u00f3n de ecosistemas como el Humedal de Bucalemu.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2026 - Diciembre 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26909\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Biosurveillance costera de la Regi\u00f3n de O&#8217;Higgins: desarrollo de una herramienta de evaluaci\u00f3n de la calidad del borde costero mediante respuestas inmunol\u00f3gicas en organismos centinela a contaminantes prioritarios\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26909\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26909\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El borde costero de la regi\u00f3n de O\u0092Higgins enfrenta un desaf\u00edo importante en cuanto a alcanzar un desarrollo\r\nsostenible a nivel ambiental. Esto se debe a la exposici\u00f3n a contaminantes como pesticidas y metales\r\nprovenientes de actividades clave de la regi\u00f3n, como lo son la agricultura y la miner\u00eda. Esta contaminaci\u00f3n\r\namenaza los ecosistemas del borde costero, la biodiversidad, la salud p\u00fablica y las actividades econ\u00f3micas\r\nfundamentales como la pesca artesanal y el turismo. A pesar de la magnitud del problema, existe escasa\r\ninformaci\u00f3n sobre los contaminantes presentes en este ambiente. La ausencia de sistemas de monitoreo\r\nlimita la caracterizaci\u00f3n de la presencia de contaminantes y la evaluaci\u00f3n de sus efectos sobre los ecosistemas\r\ncosteros. Esta brecha dificulta la implementaci\u00f3n de estrategias efectivas de gesti\u00f3n ambiental y pone en\r\nriesgo la sostenibilidad de las comunidades costeras que dependen de estos recursos naturales.\r\nEl proyecto propone desarrollar una herramienta de biosurveillance adaptada a las caracter\u00edsticas espec\u00edficas\r\ndel borde costero regional, inspirada en el exitoso modelo franc\u00e9s BIOSURVEILLANCE que utiliza organismos\r\ncentinelas para evaluar la calidad del agua. La iniciativa busca establecer un sistema piloto de monitoreo que\r\ncombine an\u00e1lisis qu\u00edmicos de contaminantes con evaluaci\u00f3n de biomarcadores inmunol\u00f3gicos en mejillones,\r\norganismos filtradores que bioacumulan contaminantes y que sirven como reflejo del estado de salud del\r\necosistema.\r\nEl objetivo general del proyecto es evaluar el estado de salud inmunol\u00f3gico de organismos centinela del borde\r\ncostero de la Regi\u00f3n de O'Higgins y su relaci\u00f3n con la presencia de contaminantes, desarrollando un piloto de\r\nbiosurveillance transferible a la gesti\u00f3n ambiental y acuicultura. Este proyecto cuenta con cuatro objetivos\r\nespec\u00edficos: (1) caracterizar la presencia y concentraci\u00f3n de contaminantes persistentes (metales y pesticidas)\r\nen agua, sedimentos y biota; (2) evaluar las respuestas inmunol\u00f3gicas en organismos centinela mediante\r\nbiomarcadores moleculares; (3) analizar la relaci\u00f3n entre contaminantes espec\u00edficos y respuestas\r\ninmunol\u00f3gicas para identificar biomarcadores sensibles y robustos; y (4) desarrollar un piloto de\r\nbiosurveillance con potencial de transferencia a programas de gesti\u00f3n regional y nacional.\r\nPara llevar a cabo este proyecto se implementar\u00e1 un sistema de encajonamiento de mejillones (Mytilus edulis\r\no M. chilensis) en tres sitios estrat\u00e9gicos del borde costero: Navidad, Pichilemu y Bucalemu. Estos sitios\r\nrepresentan puntos cr\u00edticos de confluencia entre aportes continentales y ecosistema marino, permitiendo\r\nevaluar efectos acumulativos de contaminaci\u00f3n. Se realizar\u00e1n dos campa\u00f1as de muestreo (invierno y verano)\r\npara capturar variaci\u00f3n temporal. En cada sitio se colocar\u00e1n individuos adultos en jaulas durante 15 d\u00edas,\r\nper\u00edodo tras el cual se recuperar\u00e1n para an\u00e1lisis qu\u00edmicos y biol\u00f3gicos.\r\nEl componente qu\u00edmico incluir\u00e1 an\u00e1lisis de metales mediante espectrometr\u00eda (ICP-OES) y pesticidas mediante\r\ncromatograf\u00eda (LC-MS\/MS) en matrices de agua, sedimentos y tejidos. Paralelamente, se caracterizar\u00e1n\r\npar\u00e1metros fisicoqu\u00edmicos (pH, conductividad, temperatura, ox\u00edgeno disuelto, salinidad) para contextualizar\r\nbiogeoqu\u00edmicamente los sitios.\r\nEl componente biol\u00f3gico evaluar\u00e1 biomarcadores de respuesta inmune mediante an\u00e1lisis de expresi\u00f3n g\u00e9nica\r\npor qPCR de genes relacionados con estr\u00e9s oxidativo (catalasa, super\u00f3xido dismutasa, glutati\u00f3n S-transferasa,\r\nmetalotione\u00ednas) en tejidos de mejillones. Estos biomarcadores son sensibles a la exposici\u00f3n a metales y\r\npesticidas, proporcionando indicadores tempranos de estr\u00e9s ambiental.\r\nLa integraci\u00f3n de datos qu\u00edmicos y biol\u00f3gicos se realizar\u00e1 mediante an\u00e1lisis estad\u00edsticos multivariados y\r\nmatrices de correlaci\u00f3n utilizando lenguaje de programaci\u00f3n (Phyton y R), identificando relaciones causales\r\nentre contaminantes espec\u00edficos y activaci\u00f3n del sistema inmune. Esta aproximaci\u00f3n permitir\u00e1 seleccionar los\r\nbiomarcadores m\u00e1s apropiados seg\u00fan ubicaci\u00f3n geogr\u00e1fica y estacionalidad, estableciendo las bases para un\r\nsistema de alerta temprana aplicable a la gesti\u00f3n costera regional.\r\nEl proyecto tiene una duraci\u00f3n de 18 meses y representa una iniciativa interdisciplinaria que integra Ciencias\r\ndel Medio Ambiente, Biolog\u00eda Marina y Matem\u00e1tica Aplicada, contribuyendo directamente a la sostenibilidad\r\nambiental del borde costero regional y generando conocimiento transferible para futuros programas de\r\nmonitoreo a escala nacional.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FONDECYT Regular 1260171<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2026 - Marzo 2029<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26922\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fondecyt Regular: Pr\u00e1cticas art\u00edsticas de mediaci\u00f3n expandida desde contextos educativos: Oportunidades y desaf\u00edos para ampliar el rol social de las artes en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26922\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26922\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Esta investigaci\u00f3n busca conocer las formas en que las escuelas se pueden desempe\u00f1ar como espacios culturales en sus comunidades locales, para lo cual se analizar\u00e1n c\u00f3mo las pr\u00e1cticas art\u00edsticas de mediaci\u00f3n expandida se muestr\u00e1n como una herramienta y metodolog\u00eda id\u00f3nea para su desarrollo e impacto local.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2026 - Diciembre 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27031\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Biosurveillance costera de la Regi\u00f3n de O&#8217;Higgins: desarrollo de una herramienta de evaluaci\u00f3n de la calidad del borde costero mediante respuestas inmunol\u00f3gicas en organismos centinela a contaminantes prioritarios\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27031\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27031\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El borde costero de la regi\u00f3n de O\u0092Higgins enfrenta un desaf\u00edo importante en cuanto a alcanzar un desarrollo\r\nsostenible a nivel ambiental. Esto se debe a la exposici\u00f3n a contaminantes como pesticidas y metales\r\nprovenientes de actividades clave de la regi\u00f3n, como lo son la agricultura y la miner\u00eda. Esta contaminaci\u00f3n\r\namenaza los ecosistemas del borde costero, la biodiversidad, la salud p\u00fablica y las actividades econ\u00f3micas\r\nfundamentales como la pesca artesanal y el turismo. A pesar de la magnitud del problema, existe escasa\r\ninformaci\u00f3n sobre los contaminantes presentes en este ambiente. La ausencia de sistemas de monitoreo\r\nlimita la caracterizaci\u00f3n de la presencia de contaminantes y la evaluaci\u00f3n de sus efectos sobre los ecosistemas\r\ncosteros. Esta brecha dificulta la implementaci\u00f3n de estrategias efectivas de gesti\u00f3n ambiental y pone en\r\nriesgo la sostenibilidad de las comunidades costeras que dependen de estos recursos naturales.\r\nEl proyecto propone desarrollar una herramienta de biosurveillance adaptada a las caracter\u00edsticas espec\u00edficas\r\ndel borde costero regional, inspirada en el exitoso modelo franc\u00e9s BIOSURVEILLANCE que utiliza organismos\r\ncentinelas para evaluar la calidad del agua. La iniciativa busca establecer un sistema piloto de monitoreo que\r\ncombine an\u00e1lisis qu\u00edmicos de contaminantes con evaluaci\u00f3n de biomarcadores inmunol\u00f3gicos en mejillones,\r\norganismos filtradores que bioacumulan contaminantes y que sirven como reflejo del estado de salud del\r\necosistema.\r\nEl objetivo general del proyecto es evaluar el estado de salud inmunol\u00f3gico de organismos centinela del borde\r\ncostero de la Regi\u00f3n de O'Higgins y su relaci\u00f3n con la presencia de contaminantes, desarrollando un piloto de\r\nbiosurveillance transferible a la gesti\u00f3n ambiental y acuicultura. Este proyecto cuenta con cuatro objetivos\r\nespec\u00edficos: (1) caracterizar la presencia y concentraci\u00f3n de contaminantes persistentes (metales y pesticidas)\r\nen agua, sedimentos y biota; (2) evaluar las respuestas inmunol\u00f3gicas en organismos centinela mediante\r\nbiomarcadores moleculares; (3) analizar la relaci\u00f3n entre contaminantes espec\u00edficos y respuestas\r\ninmunol\u00f3gicas para identificar biomarcadores sensibles y robustos; y (4) desarrollar un piloto de\r\nbiosurveillance con potencial de transferencia a programas de gesti\u00f3n regional y nacional.\r\nPara llevar a cabo este proyecto se implementar\u00e1 un sistema de encajonamiento de mejillones (Mytilus edulis\r\no M. chilensis) en tres sitios estrat\u00e9gicos del borde costero: Navidad, Pichilemu y Bucalemu. Estos sitios\r\nrepresentan puntos cr\u00edticos de confluencia entre aportes continentales y ecosistema marino, permitiendo\r\nevaluar efectos acumulativos de contaminaci\u00f3n. Se realizar\u00e1n dos campa\u00f1as de muestreo (invierno y verano)\r\npara capturar variaci\u00f3n temporal. En cada sitio se colocar\u00e1n individuos adultos en jaulas durante 15 d\u00edas,\r\nper\u00edodo tras el cual se recuperar\u00e1n para an\u00e1lisis qu\u00edmicos y biol\u00f3gicos.\r\nEl componente qu\u00edmico incluir\u00e1 an\u00e1lisis de metales mediante espectrometr\u00eda (ICP-OES) y pesticidas mediante\r\ncromatograf\u00eda (LC-MS\/MS) en matrices de agua, sedimentos y tejidos. Paralelamente, se caracterizar\u00e1n\r\npar\u00e1metros fisicoqu\u00edmicos (pH, conductividad, temperatura, ox\u00edgeno disuelto, salinidad) para contextualizar\r\nbiogeoqu\u00edmicamente los sitios.\r\nEl componente biol\u00f3gico evaluar\u00e1 biomarcadores de respuesta inmune mediante an\u00e1lisis de expresi\u00f3n g\u00e9nica\r\npor qPCR de genes relacionados con estr\u00e9s oxidativo (catalasa, super\u00f3xido dismutasa, glutati\u00f3n S-transferasa,\r\nmetalotione\u00ednas) en tejidos de mejillones. Estos biomarcadores son sensibles a la exposici\u00f3n a metales y\r\npesticidas, proporcionando indicadores tempranos de estr\u00e9s ambiental.\r\nLa integraci\u00f3n de datos qu\u00edmicos y biol\u00f3gicos se realizar\u00e1 mediante an\u00e1lisis estad\u00edsticos multivariados y\r\nmatrices de correlaci\u00f3n utilizando lenguaje de programaci\u00f3n (Phyton y R), identificando relaciones causales\r\nentre contaminantes espec\u00edficos y activaci\u00f3n del sistema inmune. Esta aproximaci\u00f3n permitir\u00e1 seleccionar los\r\nbiomarcadores m\u00e1s apropiados seg\u00fan ubicaci\u00f3n geogr\u00e1fica y estacionalidad, estableciendo las bases para un\r\nsistema de alerta temprana aplicable a la gesti\u00f3n costera regional.\r\nEl proyecto tiene una duraci\u00f3n de 18 meses y representa una iniciativa interdisciplinaria que integra Ciencias\r\ndel Medio Ambiente, Biolog\u00eda Marina y Matem\u00e1tica Aplicada, contribuyendo directamente a la sostenibilidad\r\nambiental del borde costero regional y generando conocimiento transferible para futuros programas de\r\nmonitoreo a escala nacional.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2026 - Diciembre 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27057\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Biosurveillance costera de la Regi\u00f3n de O&#8217;Higgins: desarrollo de una herramienta de evaluaci\u00f3n de la calidad del borde costero mediante respuestas inmunol\u00f3gicas en organismos centinela a contaminantes prioritarios\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27057\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27057\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El borde costero de la regi\u00f3n de O\u0092Higgins enfrenta un desaf\u00edo importante en cuanto a alcanzar un desarrollo\r\nsostenible a nivel ambiental. Esto se debe a la exposici\u00f3n a contaminantes como pesticidas y metales\r\nprovenientes de actividades clave de la regi\u00f3n, como lo son la agricultura y la miner\u00eda. Esta contaminaci\u00f3n\r\namenaza los ecosistemas del borde costero, la biodiversidad, la salud p\u00fablica y las actividades econ\u00f3micas\r\nfundamentales como la pesca artesanal y el turismo. A pesar de la magnitud del problema, existe escasa\r\ninformaci\u00f3n sobre los contaminantes presentes en este ambiente. La ausencia de sistemas de monitoreo\r\nlimita la caracterizaci\u00f3n de la presencia de contaminantes y la evaluaci\u00f3n de sus efectos sobre los ecosistemas\r\ncosteros. Esta brecha dificulta la implementaci\u00f3n de estrategias efectivas de gesti\u00f3n ambiental y pone en\r\nriesgo la sostenibilidad de las comunidades costeras que dependen de estos recursos naturales.\r\nEl proyecto propone desarrollar una herramienta de biosurveillance adaptada a las caracter\u00edsticas espec\u00edficas\r\ndel borde costero regional, inspirada en el exitoso modelo franc\u00e9s BIOSURVEILLANCE que utiliza organismos\r\ncentinelas para evaluar la calidad del agua. La iniciativa busca establecer un sistema piloto de monitoreo que\r\ncombine an\u00e1lisis qu\u00edmicos de contaminantes con evaluaci\u00f3n de biomarcadores inmunol\u00f3gicos en mejillones,\r\norganismos filtradores que bioacumulan contaminantes y que sirven como reflejo del estado de salud del\r\necosistema.\r\nEl objetivo general del proyecto es evaluar el estado de salud inmunol\u00f3gico de organismos centinela del borde\r\ncostero de la Regi\u00f3n de O'Higgins y su relaci\u00f3n con la presencia de contaminantes, desarrollando un piloto de\r\nbiosurveillance transferible a la gesti\u00f3n ambiental y acuicultura. Este proyecto cuenta con cuatro objetivos\r\nespec\u00edficos: (1) caracterizar la presencia y concentraci\u00f3n de contaminantes persistentes (metales y pesticidas)\r\nen agua, sedimentos y biota; (2) evaluar las respuestas inmunol\u00f3gicas en organismos centinela mediante\r\nbiomarcadores moleculares; (3) analizar la relaci\u00f3n entre contaminantes espec\u00edficos y respuestas\r\ninmunol\u00f3gicas para identificar biomarcadores sensibles y robustos; y (4) desarrollar un piloto de\r\nbiosurveillance con potencial de transferencia a programas de gesti\u00f3n regional y nacional.\r\nPara llevar a cabo este proyecto se implementar\u00e1 un sistema de encajonamiento de mejillones (Mytilus edulis\r\no M. chilensis) en tres sitios estrat\u00e9gicos del borde costero: Navidad, Pichilemu y Bucalemu. Estos sitios\r\nrepresentan puntos cr\u00edticos de confluencia entre aportes continentales y ecosistema marino, permitiendo\r\nevaluar efectos acumulativos de contaminaci\u00f3n. Se realizar\u00e1n dos campa\u00f1as de muestreo (invierno y verano)\r\npara capturar variaci\u00f3n temporal. En cada sitio se colocar\u00e1n individuos adultos en jaulas durante 15 d\u00edas,\r\nper\u00edodo tras el cual se recuperar\u00e1n para an\u00e1lisis qu\u00edmicos y biol\u00f3gicos.\r\nEl componente qu\u00edmico incluir\u00e1 an\u00e1lisis de metales mediante espectrometr\u00eda (ICP-OES) y pesticidas mediante\r\ncromatograf\u00eda (LC-MS\/MS) en matrices de agua, sedimentos y tejidos. Paralelamente, se caracterizar\u00e1n\r\npar\u00e1metros fisicoqu\u00edmicos (pH, conductividad, temperatura, ox\u00edgeno disuelto, salinidad) para contextualizar\r\nbiogeoqu\u00edmicamente los sitios.\r\nEl componente biol\u00f3gico evaluar\u00e1 biomarcadores de respuesta inmune mediante an\u00e1lisis de expresi\u00f3n g\u00e9nica\r\npor qPCR de genes relacionados con estr\u00e9s oxidativo (catalasa, super\u00f3xido dismutasa, glutati\u00f3n S-transferasa,\r\nmetalotione\u00ednas) en tejidos de mejillones. Estos biomarcadores son sensibles a la exposici\u00f3n a metales y\r\npesticidas, proporcionando indicadores tempranos de estr\u00e9s ambiental.\r\nLa integraci\u00f3n de datos qu\u00edmicos y biol\u00f3gicos se realizar\u00e1 mediante an\u00e1lisis estad\u00edsticos multivariados y\r\nmatrices de correlaci\u00f3n utilizando lenguaje de programaci\u00f3n (Phyton y R), identificando relaciones causales\r\nentre contaminantes espec\u00edficos y activaci\u00f3n del sistema inmune. Esta aproximaci\u00f3n permitir\u00e1 seleccionar los\r\nbiomarcadores m\u00e1s apropiados seg\u00fan ubicaci\u00f3n geogr\u00e1fica y estacionalidad, estableciendo las bases para un\r\nsistema de alerta temprana aplicable a la gesti\u00f3n costera regional.\r\nEl proyecto tiene una duraci\u00f3n de 18 meses y representa una iniciativa interdisciplinaria que integra Ciencias\r\ndel Medio Ambiente, Biolog\u00eda Marina y Matem\u00e1tica Aplicada, contribuyendo directamente a la sostenibilidad\r\nambiental del borde costero regional y generando conocimiento transferible para futuros programas de\r\nmonitoreo a escala nacional.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1260911<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2026 - Marzo 2029<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27095\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            La coherencia relacional en la escritura argumentativa de aprendientes de espa\u00f1ol como lengua adicional (ELA)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27095\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27095\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto sobre an\u00e1lisis de coherencia relacional en textos de aprendientes de espa\u00f1ol como lengua adicional[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FONDART Nacional de Investigaci\u00f3n 815489<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2026 - Mayo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Fondart Nacional de Investigaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27113\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fondart Investigaci\u00f3n: Pr\u00e1cticas art\u00edsticas colaborativas desde la escuela: aportes y desaf\u00edos para expandir las artes en el territorio\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27113\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27113\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto analizar\u00e1 las dimensiones del arte colaborativo en escuelas de la regi\u00f3n de O`Higgins y Metropolitana[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FONDECYT Regular 1260171<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2026 - Marzo 2029<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27114\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fondecyt Regular: Pr\u00e1cticas art\u00edsticas de mediaci\u00f3n expandida desde contextos educativos: Oportunidades y desaf\u00edos para ampliar el rol social de las artes en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27114\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27114\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Esta investigaci\u00f3n busca conocer las formas en que las escuelas se pueden desempe\u00f1ar como espacios culturales en sus comunidades locales, para lo cual se analizar\u00e1n c\u00f3mo las pr\u00e1cticas art\u00edsticas de mediaci\u00f3n expandida se muestr\u00e1n como una herramienta y metodolog\u00eda id\u00f3nea para su desarrollo e impacto local.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2026 - Noviembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26142\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Proyecto de Innovaci\u00f3n para el Manejo de Huertos Productivos Agroecol\u00f3gicos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26142\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26142\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto busca implementar un plan de innovaci\u00f3n social y t\u00e9cnica que permita rehabilitar los suelos y fortalecer la autogesti\u00f3n de los peque\u00f1os agricultores agroecol\u00f3gicos en la comuna de Marchig\u00fce.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2026 - Noviembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26558\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Proyecto de Innovaci\u00f3n para el Manejo de Huertos Productivos Agroecol\u00f3gicos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26558\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26558\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto busca implementar un plan de innovaci\u00f3n social y t\u00e9cnica que permita rehabilitar los suelos y fortalecer la autogesti\u00f3n de los peque\u00f1os agricultores agroecol\u00f3gicos en la comuna de Marchig\u00fce.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2026 - Agosto 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>ARA Adaptarion Research Alliance<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27100\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Co-producing adaptation knowledge in Latin America: Empowering Early-career researchers and local voices for IPCC AR7\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27100\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27100\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"].[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 2024\/19635-0<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Febrero 2026 - Febrero 2031<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>S\u00e3o Paulo Research Foundation | FAPESP<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27016\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Solutions for mitigating and adapting agricultural crops and pastures to a future climate scenario of a 2\u00b0C temperature increase, by inoculating plants with nitrogen-fixing and plant growth-promoting bacteria\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27016\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27016\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Anthropogenic climate change and its impacts on managed ecosystems pose a threat to global food security and the sustainability of farming systems. Rising temperatures, combined with more frequent and intense extreme weather events such as droughts and heatwaves, compromise agricultural productivity, the nutritional quality of food and its supply, raising costs and exposing the most vulnerable populations to food insecurity. Rising temperatures also impact the flow of greenhouse gases in ecosystems, both due to changes in the rate of carbon assimilation in biomass and changes in the rates of carbon dioxide, nitrous oxide and methane emissions from the soil. In recent decades, the technology of inoculating seeds with nitrogen-fixing (BFN) and plant growth-promoting (BPCV) bacteria, such as Bradyrhizobium spp. in legumes and Azospirillum brasilense and Pseudomonas fluorescens in grasses, has shown promising results, both by increasing productivity and by making plants more resilient to abiotic stresses. In this way, inoculation has the potential to mitigate the effects of the rise in temperature predicted for the coming decades. This mitigation potential will depend on both the magnitude of the temperature increase and the ability of these cultivated species to acclimatize in a heated atmosphere. Inoculation techniques also substantially reduce the use of nitrogen fertilizers, contributing to the mitigation of global warming by reducing nitrous oxide emissions from the soil. In this proposal, we will evaluate how agricultural crops and pastures of recognized economic importance, such as soybeans, sorghum, corn and Mombasa grass, will be impacted by a temperature increase of +2 \u00b0C and how the inoculation of BFN and BPCV can mitigate or amplify these effects. Physiological, nutritional, biochemical, plant growth and productivity parameters will be assessed, as well as the impacts on the soil microbiota and microclimate, and the emission of greenhouse gases in each crop. The experiments will be conducted under field conditions, using the outdoor plant heating system (T-FACE), in which automatically regulated infrared heaters keep the plants warm at +2 \u00b0C above the ambient temperature. This system is the only one in Latin America that allows temperature manipulation in field conditions, without physical limitations that alter the microclimate or restrictions on root growth, and is an excellent tool for studying the impact of future temperature increases in managed ecosystems. The results of this study will contribute to a more precise understanding of the future impacts of rising temperatures on the country's main agricultural crops and the potential for mitigating these effects by inoculating plants with nitrogen-fixing and plant growth-promoting bacteria. These results could strengthen Brazilian agriculture, improving its resilience and increasing its competitiveness on the international stage. This previously unpublished data could improve the management of these species in the face of future climate change scenarios and provide important data for decision-makers.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> SiAgro 126RT0191<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Febrero 2026 - Febrero 2030<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Programa Iberoamericano de Ciencia y Tecnolog\u00eda para el Desarrollo (CYTED)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27017\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27017\" aria-expanded=\"false\" aria-controls=\"collapse-27017\">\n                                            SiAgro &#8211; Red iberoamericana sobre el uso del silicio en la mitigaci\u00f3n de estreses m\u00faltiples, fortaleciendo la sostenibilidad agroalimentaria de la regi\u00f3n\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27017\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27017\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La Red Iberoamericana CYTED coordinada por Renato de Mello Prado (UNESP, Brasil) integra 15 grupos y 51 investigadores de Brasil, Chile, Colombia, Ecuador, M\u00e9xico, Paraguay, Per\u00fa, Portugal y Uruguay para fomentar la colaboraci\u00f3n en fertilidad de suelos, nutrici\u00f3n vegetal y manejo sustentable de cultivos, articulando universidades, institutos como Embrapa e INIA, universidades nacionales e internacionales y agencias de extensi\u00f3n. Dentro de este marco, el proyecto propuesto \"El silicio es una estrategia para mitigar estreses para la sostenibilidad agroalimentaria de cultivos en Brasil, Per\u00fa, Paraguay, Colombia, Ecuador y Chile\" (SiAgro, 2026-2029) posiciona el silicio como herramienta clave para enfrentar sequ\u00eda, salinidad, enfermedades y deficiencias nutricionales en cultivos como ma\u00edz, arroz y ca\u00f1a, validando dosis y formas de aplicaci\u00f3n (foliar, radicular, nano-Si), estudiando mecanismos fisiol\u00f3gicos, bioqu\u00edmicos, moleculares (transportadores Lsi1\/Lsi2, pared celular, antioxidantes) y promoviendo transferencia tecnol\u00f3gica para peque\u00f1os productores, con \u00e9nfasis en resiliencia clim\u00e1tica en suelos volc\u00e1nicos, aluviales y tropicales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Ciencia, Tecnolog\u00eda, Conocimiento e Innovaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26317\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Exposici\u00f3n dietaria a micotoxinas en lactantes hasta 24 meses en Chile: determinaci\u00f3n en f\u00f3rmulas l\u00e1cteas, preparados y cereales mediante HPLC-MS\/MS\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26317\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26317\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Se han identificado m\u00e1s de 400 micotoxinas, qu\u00edmicamente\r\nestables y habituales en alimentos, con efectos\r\ncomprobados de carcinogenicidad, inmunosupresi\u00f3n,\r\ndisrupci\u00f3n endocrina, genotoxicidad,\r\nneurotoxicidad y alteraciones en el crecimiento,\r\ndesarrollo y reproducci\u00f3n. En este contexto, la\r\nbaja natalidad en Chile acent\u00faa la necesidad de\r\nproteger la infancia temprana(0-24 meses), etapa en\r\nque f\u00f3rmulas, preparados y cereales constituyen\r\nuna fuente de exposici\u00f3n.\r\nLa evidencia internacional confirma su alta\r\npresencia en alimentos infantiles. En Chile, aunque\r\nlos estudios son limitados, se ha detectado\r\naflatoxinaM1, ocratoxinaA, deoxinivalenol y\r\nzearalenona. Sin embargo, el Reglamento Sanitario\r\nde los Alimentos(RSA) considera menos micotoxinas,\r\ncon l\u00edmites mucho menos estrictos que la UE y sin\r\nenfoque en la infancia, generando una brecha\r\nregulatoria. Este estudio, en l\u00ednea con la\r\nEstrategia Nacional de Salud 2021-2030\r\n(alimentaci\u00f3n inocua, prevenci\u00f3n de ECNT y\r\ndesarrollo infantil), dotar\u00e1 al ISP de capacidades\r\nde vigilancia, fiscalizaci\u00f3n, investigaci\u00f3n,\r\ntransferencia tecnol\u00f3gica y referencia, mediante\r\nHPLC-MS\/MS validado para 19 micotoxinas reguladas y\r\nemergentes.\r\nObjetivo: Evaluar el riesgo por exposici\u00f3n\r\ndietaria a micotoxinas en menores de 24 meses,\r\nmediante su determinaci\u00f3n en f\u00f3rmulas l\u00e1cteas,\r\nalimentos preparados y cereales infantiles\r\ncomercializados en Chile.\r\nM\u00e9todos: Estudio transversal; muestreo\r\nestratificado(300 muestras); an\u00e1lisis HPLC-MS\/MS\r\nseg\u00fan norma UE para 19 micotoxinas(reguladas y\r\nemergentes); comparaci\u00f3n regulatoria, c\u00e1lculo de\r\nIDE(&#956;g\/kg-d\u00eda) y caracterizaci\u00f3n del\r\nriesgo(HQ\/MOE).\r\nResultados esperados: l\u00ednea base nacional de\r\nmicotoxinas en alimentos infantiles por HPLC-MS\/MS;\r\nidentificaci\u00f3n de ocurrencias y co-ocurrencias;\r\ncomparaci\u00f3n con l\u00edmites UE; estimaci\u00f3n de\r\nexposici\u00f3n y riesgo por grupo etario; y evidencia\r\ncient\u00edfica para actualizar el RSA, reduciendo\r\nriesgos y orientando pol\u00edticas p\u00fablicas en\r\nprotecci\u00f3n infantil.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2026 - Enero 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Pacific hydro<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26381\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Xenopus laevis como centinela de riesgo sanitario por quitridiomicosis en la cuenca del r\u00edo Cachapoal: comparaci\u00f3n de sitios con y sin invasora\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26381\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26381\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La quitridiomicosis, causada por el hongo qu\u00edtrido Batrachochytrium dendrobatidis\r\n(Bd), es una amenaza sanitaria relevante para anfibios y se ha convertido en un\r\ntema central de conservaci\u00f3n porque puede afectar la supervivencia, la salud y la\r\ndin\u00e1mica de poblaciones. Aun cuando no siempre se observan mortalidades\r\nevidentes, Bd puede permanecer en el ambiente y circular en hospedadores con\r\ndistinta susceptibilidad, generando escenarios silenciosos de riesgo. En Chile\r\nexiste evidencia de Bd y, en la pr\u00e1ctica, la pregunta ya no es si el pat\u00f3geno \u0093podr\u00eda\r\nllegar\u0094, sino c\u00f3mo se comporta en condiciones reales de terreno: en qu\u00e9\r\nambientes aparece, con qu\u00e9 frecuencia, si se concentra en ciertos periodos del\r\na\u00f1o y qu\u00e9 condiciones ambientales se asocian a su detecci\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26767\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Instituto Milenio ASOR\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26767\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26767\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetivo del Instituto Milenio Autoridad y Regulaci\u00f3n Social (ASOR) es desarrollar investigaci\u00f3n interdisciplinaria de\r\nfrontera sobre la desestabilizaci\u00f3n y reconfiguraci\u00f3n de la autoridad en la sociedad chilena y sus impactos en la\r\nregulaci\u00f3n social. Las tensiones en la autoridad se manifiestan, por ejemplo, en el cuestionamiento de la autoridad\r\nescolar, el impacto de la autoridad digital en roles de autoridad, o el ascenso de liderazgos autoritarios. Comprender\r\nestos desaf\u00edos es esencial para la coordinaci\u00f3n de tareas sociales, fortalecer la gobernabilidad democr\u00e1tica y mejorar\r\nel bienestar colectivo.\r\nASOR abordar\u00e1 las brechas en el estudio de la autoridad desarrollando un modelo explicativo sobre su reconfiguraci\u00f3n\r\nen las sociedades contempor\u00e1neas y aportando a su renovaci\u00f3n conceptual. El Instituto afrontar\u00e1 su complejidad\r\nadoptando un marco te\u00f3rico y metodol\u00f3gico multi-esfera y multi-nivel, y examinando factores socio-estructurales e\r\nhist\u00f3ricos, con especial atenci\u00f3n a las tecnolog\u00edas digitales.\r\nLas 4 l\u00edneas de investigaci\u00f3n de ASOR son: Autoridad y Vida Social; Autoridad y Seguridad; Autoridad y Pol\u00edtica y\r\nAutoridad, Tecnolog\u00edas Digitales y el Mundo Digital. El trabajo del Instituto abarca Producci\u00f3n, Integraci\u00f3n y Traducci\u00f3n\r\nde conocimientos. La producci\u00f3n de conocimientos aplicar\u00e1 una metodolog\u00eda basada en 8 principios: multi-actor, multi-\r\nespacial, longitudinal, interdisciplinaria, m\u00e9todos mixtos, an\u00e1lisis socio-estructural e hist\u00f3rico, y consideraci\u00f3n de\r\nfactores generacionales, socioecon\u00f3micos y de g\u00e9nero, todos alineados con los principios de la ciencia abierta. La\r\nintegraci\u00f3n se facilitar\u00e1 a trav\u00e9s de estudios espec\u00edficos y transversales, triangulaci\u00f3n metodol\u00f3gica y publicaciones\r\ncolaborativas para producir teor\u00eda que enriquezca el debate cient\u00edfico nacional e internacional. La traducci\u00f3n incluir\u00e1 el\r\nmonitoreo de pol\u00edticas p\u00fablicas, identificaci\u00f3n de necesidades sociales y colaboraci\u00f3n con instituciones\r\ngubernamentales y actores sociales para influir en pol\u00edticas p\u00fablicas y crear herramientas metodol\u00f3gicas efectivas.\r\nLa formaci\u00f3n de capital humano integrar\u00e1 a investigadores j\u00f3venes y estudiantes en espacios de trabajo colaborativos,\r\nbrind\u00e1ndoles herramientas para su desarrollo profesional y cient\u00edfico y su inserci\u00f3n en redes nacionales e\r\ninternacionales. ASOR desarrollar\u00e1 redes formales de colaboraci\u00f3n con acad\u00e9micos internacionales, centros de\r\ninvestigaci\u00f3n y organizaciones gubernamentales. Tambi\u00e9n generar\u00e1 estrategias de divulgaci\u00f3n y transferencia de\r\nconocimiento cient\u00edfico, asesor\u00edas e impacto en pol\u00edticas p\u00fablicas. Los principios rectores de ASOR priorizar\u00e1n la\r\nequidad de g\u00e9nero y territorial. El Instituto aspira a convertirse en un referente cient\u00edfico internacional, produciendo\r\ninvestigaciones innovadoras y de alta calidad, fomentando la colaboraci\u00f3n global y generando conocimiento\r\nsocialmente relevante para mejorar las experiencias cotidianas de los individuos en las diversas esferas en que sus\r\nvidas se desarrollan.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> INTER0425<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2026 - Junio 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26492\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            El bosque como archivo volc\u00e1nico: reconstrucci\u00f3n del registro eruptivo reciente del campo Carr\u00e1n-Los Venados (Regi\u00f3n de los R\u00edos, Chile) a partir del an\u00e1lisis dendrocronol\u00f3gico y dendroqu\u00edmico de anillos de \u00e1rboles Nothofagus.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26492\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26492\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las erupciones volc\u00e1nicas, entre otros procesos naturales como variaciones en el clima, sismos, incendios, incluso ataques de insectos o talas selectivas, generan anomal\u00edas de crecimiento en los \u00e1rboles que se traducen en variaciones del ancho de los anillos de crecimiento, como su disminuci\u00f3n (supresi\u00f3n), ausencia de ellos o, en algunos casos, aumento de su dimensi\u00f3n (liberaci\u00f3n). Por su parte, las erupciones volc\u00e1nicas, adem\u00e1s de generar un efecto f\u00edsico en el crecimiento, generan cambios en la qu\u00edmica del suelo, que se ver\u00e1n manifestados como anomal\u00edas qu\u00edmicas en los \u00e1rboles, como aumento de concentraciones de metales, tales como azufre, cinc, cobre, manganeso, hierro y f\u00f3sforo.\r\nUna de las zonas volc\u00e1nicas m\u00e1s activas de Chile es el Campo Volc\u00e1nico monogen\u00e9tico (distribuido) Carr\u00e1n-Los Venados (CVCLV; Regi\u00f3n de Los R\u00edos, Chile), encontr\u00e1ndose en el puesto 6\u00b0 del Ranking de Riesgo Espec\u00edfico elaborado por Sernageomin en 2023. El conocimiento sobre la historia eruptiva de CVCLV es limitado debido a la escasez de registros hist\u00f3ricos y a la falta de dataciones precisas de sus productos volc\u00e1nicos. Solo se cuenta con tres erupciones documentadas en el siglo XX (1907, 1955 y 1979), mientras que el registro prehist\u00f3rico se ha reconstruido principalmente mediante an\u00e1lisis tefroestratigr\u00e1ficos y dataciones radiom\u00e9tricas por 14C en suelos y carbones, las cuales presentan una resoluci\u00f3n temporal baja y m\u00e1rgenes de incertidumbre de hasta 30-100 a\u00f1os. Esta limitada precisi\u00f3n impide establecer con detalle la cronolog\u00eda eruptiva y las tasas de recurrencia del CVCLV, dificultando as\u00ed la comprensi\u00f3n de su comportamiento eruptivo y la evaluaci\u00f3n de los peligros volc\u00e1nicos asociados, por lo que un m\u00e9todo alternativo m\u00e1s preciso para datar erupciones volc\u00e1nicas pasadas es la dendrocronolog\u00eda, o el estudio de los anillos de los \u00e1rboles.\r\nPor tanto, el objetivo principal de este proyecto es identificar la actividad eruptiva previa al siglo XX del campo volc\u00e1nico a partir de aproximaciones metodol\u00f3gicas en dendrocronolog\u00eda y qu\u00edmica elemental (dendroqu\u00edmica). En particular, se busca identificar anomal\u00edas en el crecimiento radial de \u00e1rboles del g\u00e9nero Nothofagus en respuesta a erupciones volc\u00e1nicas acontecidas, junto con la evaluaci\u00f3n de concentraciones de metales (ej.: cobre, zinc, plomo, etc.) en anillos de crecimiento de a\u00f1os clave. Se espera identificar una se\u00f1al distinguible posible de asociar a las registradas en los anillos en el registro hist\u00f3rico, que permita extender el registro eruptivo de la zona de Carr\u00e1n-Los Venados en los \u00faltimos 500 a\u00f1os y, determinar as\u00ed, la frecuencia eruptiva actual del campo monogen\u00e9tico, lo que contribuye al entendimiento del comportamiento eruptivo y a la posible actualizaci\u00f3n de su estado de peligro volc\u00e1nico, para poder generar medidas de mitigaciones para erupciones futura.\r\nLa metodolog\u00eda consiste en la construcci\u00f3n de una cronolog\u00eda regional de ancho de anillo de crecimiento de \u00e1rboles de Nothofagus ubicados dentro del campo volc\u00e1nico (ej. N. dombeyii, N. betuloides o N. obliqua) para detectar a\u00f1os marcadores de eventos ex\u00f3genos y cambios en las tendencias de crecimiento. Adem\u00e1s, se plantea incluir an\u00e1lisis qu\u00edmicos en a\u00f1os particulares mediante Espectrometr\u00eda de Masas con Plasma Acoplado Inductivamente (ICP-MS). Finalmente, se realizar\u00e1 el c\u00e1lculo de la frecuencia eruptiva del campo volc\u00e1nico durante los \u00faltimos 500 a\u00f1os, permitiendo construir la primera cronolog\u00eda precisa de erupciones en el campo volc\u00e1nico monogen\u00e9tico Carr\u00e1n-Los Venados.\r\nEn s\u00edntesis, esta propuesta integra enfoques de la volcanolog\u00eda y las ciencias forestales para datar y caracterizar erupciones ocurridas durante los \u00faltimos ~500 a\u00f1os en el CVCLV, mediante el uso combinado de t\u00e9cnicas dendrocronol\u00f3gicas y dendroqu\u00edmicas. Esta aproximaci\u00f3n permitir\u00e1 establecer una cronolog\u00eda eruptiva detallada, identificar los elementos qu\u00edmicos que afectan el crecimiento arb\u00f3reo tras el dep\u00f3sito de cenizas o tefras, y contribuir as\u00ed a una comprensi\u00f3n m\u00e1s profunda de la din\u00e1mica eruptiva y de los procesos forestales en el campo monogen\u00e9tico Carr\u00e1n-Los Venados. Los resultados, adem\u00e1s, ofrecer\u00e1n una base metodol\u00f3gica aplicable a otros sistemas volc\u00e1nicos del pa\u00eds, incluyendo la Regi\u00f3n de O\u0092Higgins.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>UC<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26781\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Regenerando Suelos Salinos: Soluciones Urbanas con Biofertilizantes, Energ\u00eda Solar y Agua de Niebla\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26781\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26781\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En Chile, la relaci\u00f3n entre suelo y clima es cr\u00edtica por su diversidad edafoclim\u00e1tica. El cambio clim\u00e1tico intensifica variaciones de temperatura y precipitaciones, afectando la estructura, fertilidad y capacidad de retenci\u00f3n h\u00eddrica de los suelos. En la zona centro-norte, se observan procesos como desertificaci\u00f3n, salinizaci\u00f3n y p\u00e9rdida de materia org\u00e1nica, comprometiendo la productividad agr\u00edcola. Los suelos salinos del norte, clasificados como Aridisoles, contienen alta salinidad, baja materia org\u00e1nica y textura arenosa, lo que exige soluciones regenerativas que promuevan la salud y funcionalidad de estos suelos. Una alternativa es el uso de biodigestores urbanos, sistemas que transforman residuos org\u00e1nicos en biog\u00e1s y biofertilizante, mejorando las propiedades fisicoqu\u00edmicas del suelo, estimulando la actividad microbiana en l\u00ednea con la econom\u00eda circular. Sin embargo, es necesaria la gesti\u00f3n del d\u00e9ficit h\u00eddrico para tal estimulaci\u00f3n. En este contexto, Een el Mercado Urbano Tobalaba, opera un biodigestor que procesa biomasa de locales gastron\u00f3micos, gestionado por la empresa Schwager. Este modelo de estudio se utilizar\u00e1 para evaluar la recuperaci\u00f3n de suelos degradados en la estaci\u00f3n Atacama UC, as\u00ed como su impacto social, ambiental y econ\u00f3mico. En dicha estaci\u00f3n, el agua de niebla se capta pasivamente como fuente h\u00eddrica alternativa, utiliz\u00e1ndose para el riego de suelos tratados, cerrando un ciclo sostenible. Adem\u00e1s, la energ\u00eda solar, abundante en zonas \u00e1ridas, permitir\u00e1 operar con autonom\u00eda energ\u00e9tica. El objetivo es restaurar la capacidad productiva del suelo sin comprometer el equilibrio ecol\u00f3gico, contribuyendo a la regeneraci\u00f3n territorial y al cumplimiento de los Objetivos de Desarrollo Sostenible. \r\nLos resultados de este modelo de estudio constituir\u00e1n una soluci\u00f3n integral, que permite transformar residuos gastron\u00f3micos urbanos en biofertilizantes aplicables a suelos degradados. Su impacto nacional radica en la capacidad de escalar un modelo replicable, sustentable y tecnol\u00f3gicamente viable, que contribuye simult\u00e1neamente a la restauraci\u00f3n de suelos, la gesti\u00f3n eficiente de residuos org\u00e1nicos, la adaptaci\u00f3n al cambio clim\u00e1tico y el fortalecimiento de la agricultura liderada por mujeres[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> INTER0425<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2026 - Junio 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26870\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            El bosque como archivo volc\u00e1nico: reconstrucci\u00f3n del registro eruptivo reciente del campo Carr\u00e1n-Los Venados (Regi\u00f3n de los R\u00edos, Chile) a partir del an\u00e1lisis dendrocronol\u00f3gico y dendroqu\u00edmico de anillos de \u00e1rboles Nothofagus.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26870\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26870\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las erupciones volc\u00e1nicas, entre otros procesos naturales como variaciones en el clima, sismos, incendios, incluso ataques de insectos o talas selectivas, generan anomal\u00edas de crecimiento en los \u00e1rboles que se traducen en variaciones del ancho de los anillos de crecimiento, como su disminuci\u00f3n (supresi\u00f3n), ausencia de ellos o, en algunos casos, aumento de su dimensi\u00f3n (liberaci\u00f3n). Por su parte, las erupciones volc\u00e1nicas, adem\u00e1s de generar un efecto f\u00edsico en el crecimiento, generan cambios en la qu\u00edmica del suelo, que se ver\u00e1n manifestados como anomal\u00edas qu\u00edmicas en los \u00e1rboles, como aumento de concentraciones de metales, tales como azufre, cinc, cobre, manganeso, hierro y f\u00f3sforo.\r\nUna de las zonas volc\u00e1nicas m\u00e1s activas de Chile es el Campo Volc\u00e1nico monogen\u00e9tico (distribuido) Carr\u00e1n-Los Venados (CVCLV; Regi\u00f3n de Los R\u00edos, Chile), encontr\u00e1ndose en el puesto 6\u00b0 del Ranking de Riesgo Espec\u00edfico elaborado por Sernageomin en 2023. El conocimiento sobre la historia eruptiva de CVCLV es limitado debido a la escasez de registros hist\u00f3ricos y a la falta de dataciones precisas de sus productos volc\u00e1nicos. Solo se cuenta con tres erupciones documentadas en el siglo XX (1907, 1955 y 1979), mientras que el registro prehist\u00f3rico se ha reconstruido principalmente mediante an\u00e1lisis tefroestratigr\u00e1ficos y dataciones radiom\u00e9tricas por 14C en suelos y carbones, las cuales presentan una resoluci\u00f3n temporal baja y m\u00e1rgenes de incertidumbre de hasta 30-100 a\u00f1os. Esta limitada precisi\u00f3n impide establecer con detalle la cronolog\u00eda eruptiva y las tasas de recurrencia del CVCLV, dificultando as\u00ed la comprensi\u00f3n de su comportamiento eruptivo y la evaluaci\u00f3n de los peligros volc\u00e1nicos asociados, por lo que un m\u00e9todo alternativo m\u00e1s preciso para datar erupciones volc\u00e1nicas pasadas es la dendrocronolog\u00eda, o el estudio de los anillos de los \u00e1rboles.\r\nPor tanto, el objetivo principal de este proyecto es identificar la actividad eruptiva previa al siglo XX del campo volc\u00e1nico a partir de aproximaciones metodol\u00f3gicas en dendrocronolog\u00eda y qu\u00edmica elemental (dendroqu\u00edmica). En particular, se busca identificar anomal\u00edas en el crecimiento radial de \u00e1rboles del g\u00e9nero Nothofagus en respuesta a erupciones volc\u00e1nicas acontecidas, junto con la evaluaci\u00f3n de concentraciones de metales (ej.: cobre, zinc, plomo, etc.) en anillos de crecimiento de a\u00f1os clave. Se espera identificar una se\u00f1al distinguible posible de asociar a las registradas en los anillos en el registro hist\u00f3rico, que permita extender el registro eruptivo de la zona de Carr\u00e1n-Los Venados en los \u00faltimos 500 a\u00f1os y, determinar as\u00ed, la frecuencia eruptiva actual del campo monogen\u00e9tico, lo que contribuye al entendimiento del comportamiento eruptivo y a la posible actualizaci\u00f3n de su estado de peligro volc\u00e1nico, para poder generar medidas de mitigaciones para erupciones futura.\r\nLa metodolog\u00eda consiste en la construcci\u00f3n de una cronolog\u00eda regional de ancho de anillo de crecimiento de \u00e1rboles de Nothofagus ubicados dentro del campo volc\u00e1nico (ej. N. dombeyii, N. betuloides o N. obliqua) para detectar a\u00f1os marcadores de eventos ex\u00f3genos y cambios en las tendencias de crecimiento. Adem\u00e1s, se plantea incluir an\u00e1lisis qu\u00edmicos en a\u00f1os particulares mediante Espectrometr\u00eda de Masas con Plasma Acoplado Inductivamente (ICP-MS). Finalmente, se realizar\u00e1 el c\u00e1lculo de la frecuencia eruptiva del campo volc\u00e1nico durante los \u00faltimos 500 a\u00f1os, permitiendo construir la primera cronolog\u00eda precisa de erupciones en el campo volc\u00e1nico monogen\u00e9tico Carr\u00e1n-Los Venados.\r\nEn s\u00edntesis, esta propuesta integra enfoques de la volcanolog\u00eda y las ciencias forestales para datar y caracterizar erupciones ocurridas durante los \u00faltimos ~500 a\u00f1os en el CVCLV, mediante el uso combinado de t\u00e9cnicas dendrocronol\u00f3gicas y dendroqu\u00edmicas. Esta aproximaci\u00f3n permitir\u00e1 establecer una cronolog\u00eda eruptiva detallada, identificar los elementos qu\u00edmicos que afectan el crecimiento arb\u00f3reo tras el dep\u00f3sito de cenizas o tefras, y contribuir as\u00ed a una comprensi\u00f3n m\u00e1s profunda de la din\u00e1mica eruptiva y de los procesos forestales en el campo monogen\u00e9tico Carr\u00e1n-Los Venados. Los resultados, adem\u00e1s, ofrecer\u00e1n una base metodol\u00f3gica aplicable a otros sistemas volc\u00e1nicos del pa\u00eds, incluyendo la Regi\u00f3n de O\u0092Higgins.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> NCS2025_37<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2026 - Diciembre 2028<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26956\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Nucleo Milenio Discapacidad y Ciudadania\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26956\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26956\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]DISCA (Discapacidad y Ciudadan\u00eda) es un n\u00facleo que desde 2022 est\u00e1 dedicado al estudio inter y transdisciplinario de los procesos y mecanismos a trav\u00e9s de los cuales las personas con discapacidad (PcD) se transforman en ciudadanas. Su objetivo general es examinar cr\u00edticamente c\u00f3mo las PcD construyen y negocian su ciudadan\u00eda en los \u00e1mbitos de: L1. la participaci\u00f3n pol\u00edtica, L2. el acceso a la justicia y L3. el acceso a la salud mental. Cada uno de estos \u00e1mbitos ser\u00e1 una l\u00ednea de trabajo de DISCA en los tres a\u00f1os del proyecto. Una cuarta l\u00ednea se centrar\u00e1 en el uso de metodolog\u00edas inclusivas y participativas en investigaci\u00f3n en discapacidad.\r\nNuestro enfoque se basa en dos pilares. Primero, la ciudadan\u00eda como forma de integraci\u00f3n social mediante la igual consideraci\u00f3n de todos. Consideramos aspectos institucionales (derechos civiles, pol\u00edticos y sociales) y relacionales (demandas de reconocimiento). Segundo, el modelo social de la discapacidad, que busca superar el enfoque biom\u00e9dico y entiende la discapacidad como resultado de la interacci\u00f3n entre condiciones de salud o d\u00e9ficits individuales y barreras sociales que impiden la plena participaci\u00f3n de las PcD.\r\nEl modelo social no es la mirada predominante. Siguen vigentes visiones asistencialistas que restringen la inclusi\u00f3n y el ejercicio de la ciudadan\u00eda de las PcD. Es urgente que la academia cree sinergias, tanto con organizaciones de PcD como con las instituciones del Estado, para examinar las barreras que afectan a las PcD y las v\u00edas para su superaci\u00f3n. La escasez de investigaci\u00f3n en discapacidad en Chile, y la necesidad de incorporar a PcD en la generaci\u00f3n de conocimiento, hace nuestro proyecto muy relevante. La incorporaci\u00f3n de PcD en el mundo acad\u00e9mico a trav\u00e9s de DISCA es una valiosa oportunidad para realizar cambios que preparen el camino para una mayor participaci\u00f3n de otras PcD. Esperamos que sus resultados generen pol\u00edticas inclusivas y participativas en discapacidad.\r\nDISCA est\u00e1 dirigido por una PcD, cuenta con un consejo de Expertos por Experiencia (con 7 PcD) y observa los principios de la investigaci\u00f3n inclusiva y participativa. Sus investigadores principales, pioneros en la investigaci\u00f3n en discapacidad en Chile, utilizan metodolog\u00edas mixtas, cuantitativas y cualitativas, integrando conocimientos de sociolog\u00eda, derecho, salud, econom\u00eda, sociolog\u00eda y psicolog\u00eda en conjunto con el campo transdisciplinario de los estudios de la discapacidad.\r\nLos logros a corto plazo se dirigen a: i) producir investigaci\u00f3n inter y transdisciplinaria en discapacidad, ii) consolidar redes de colaboraci\u00f3n con otros centros de investigaci\u00f3n en el mundo, iii) formar capital humano en varios niveles, incluyendo PcD en todo el quehacer de DISCA y iv) informar la pol\u00edtica p\u00fablica. La meta a mediano plazo es consolidar a DISCA como el primer centro de excelencia en investigaci\u00f3n en discapacidad de Latinoam\u00e9rica, contribuyendo al fortalecimiento de los estudios de la discapacidad en el mundo.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> CIN250054<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2026 - Enero 2031<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26957\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Centro de Investigaci\u00f3n y Acci\u00f3n en Determinaci\u00f3n Social y Salud Mental\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26957\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26957\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Es un centro de excelencia en salud mental[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> CIN 250068<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2025 - Diciembre 2030<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26847\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Centro de Investigaci\u00f3n e Innovaci\u00f3n en Ni\u00f1ez, Adolescencia, Resiliencia y Adversidad (Centro IINARA)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26847\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26847\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The proposed IINARA Research Center (Investigaci\u00f3n e Innovaci\u00f3n en Ni\u00f1ez, Adolescencia, Resiliencia y Adversidad) seeks to address the pressing challenge of adversity during childhood and their profound effects on children\u0092s and adolescents\u0092 development in Chile. By combining cutting-edge research with a strong focus on public policy, capacity building, and community collaboration, the Center aims to generate actionable evidence that fosters resilience and promotes well-being among vulnerable populations that could inform public policy making. The initiative aligns with national priorities, including equitable access to developmental resources, and seeks to build a foundation for sustainable social and economic progress. \r\nAdverse Childhood Experiences\u0097ranging from abuse and neglect to socioeconomic adversity\u0097have been linked to long-term mental health issues, behavioral difficulties, and chronic illnesses. In Chile, adverse experiences are particularly prevalent in communities affected by poverty, migration, natural disasters, and systemic inequalities. Children and adolescents from indigenous and migrant populations face unique challenges, including cultural marginalization and reduced access to essential resources. Despite advancements in legal frameworks and public policies aimed at protecting children\u0092s rights, such as the \u0093Chile Crece M\u00e1s\u0094 (former Chile Crece Contigo) program, significant gaps remain in understanding the local contexts of adversity and developing targeted, evidence-based solutions.\r\nThe IINARA Center addresses these gaps through a multidisciplinary approach, integrating fields such as neuroscience, psychology, public health, and social sciences. Its mission is to understand the mechanisms underlying resilience in children and adolescents, using this knowledge to design interventions that protect vulnerable groups from the negative effects of adversity. The Center\u0092s objectives include identifying neurobiological, socioemotional, and contextual indicators of vulnerability and resilience; implementing culturally adapted interventions to promote positive developmental trajectories; and informing public policy through evidence-based recommendations. \r\nThe research will employ both qualitative methodologies, such as ethnographic studies and semi-structured interviews, and quantitative methodologies, such as the application of instruments that measure cognitive, emotional and social functioning and neuroscientific measures to understand the underlying neural mechanisms of this functioning. It will also include a randomized controlled trial (RCT) to test an intervention developed synergistically in IINARA. A significant focus will be placed on studying diverse cultural contexts that are particular to Chile, such as indigenous and migrant communities, to ensure interventions are inclusive and culturally relevant. All this will allow us to construct a model of cognitive and socioemotional functioning of children exposed to adversity across the territory, helping to guide the identification of biomarkers and predictors of resilience.\r\nThe expected impact of the IINARA Center extends across multiple dimensions. In the realm of public policy, the Center will provide robust, evidence-based recommendations for designing and implementing strategies that address childhood adversity. This includes fostering intersectoral collaboration among government agencies, educational institutions, and healthcare providers to create a comprehensive support system for children and adolescents. The Center will also strengthen capacity building by training human resources, including researchers, educators, and policymakers, in interdisciplinary approaches to childhood resilience. \r\nThrough its collaborative framework, the Center will promote associativity among academia, public institutions, and civil society organizations. By partnering with international research networks and leveraging global expertise, it will position Chile as a leader in addressing childhood adversity in Latin \r\nAmerica. The dissemination of findings will include outreach to both public and private sectors, ensuring the transfer of knowledge and technologies that benefit diverse stakeholders. By engaging communities directly in the design and implementation of interventions, the Center will foster a participatory approach that enhances the cultural relevance and sustainability of its initiatives. \r\nUltimately, the IINARA Center aspires to contribute to the development of a more resilient and equitable society by improving developmental outcomes for children and adolescents across Chile. Its work will not only reduce the long-term impact of adversity but also strengthen the country\u0092s social and economic fabric, creating opportunities for future generations to thrive.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> CIN250054<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26848\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Centro de Investigaci\u00f3n y Acci\u00f3n en Determinaci\u00f3n Social y Salud Mental (Centro CIADES)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26848\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26848\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Mental health conditions and inequities in Chile have risen significantly over recent decades, fueled\r\nby factors such as social exclusion, precarious employment, and environmental challenges. In line with recent\r\nnational legislation and policy reforms, including the recently proposed Mental Health Law (2024,) there is\r\ngrowing recognition that these issues require not only expanded clinical services but also a deeper focus on the\r\nsocio-structural determinants of mental health (Breilh, 2023; Lund et al., 2018). The Centro de Investigaci\u00f3n y\r\nAcci\u00f3n en Determinaci\u00f3n Social y Salud Mental (Center for Research and Action in Social Determination and\r\nMental Health) or CIADES responds to this urgency by adopting a Latin American\u0096rooted Social Determination\r\nof Health (SDnH) framework, thereby situating mental health vulnerabilities and risks within broader historical,\r\neconomic, and political contexts.\r\nCIADES will work in close collaboration with the Ministry of Social Development and Family (MIDESO)\r\nand the Ministry of Health (MINSAL), to generate robust evidence and policy guidance to address the social\r\nfactors that affect and produce mental health problems beyond the individual. This collaboration ensures that\r\nthe Center\u0092s research advances academic knowledge and informs public-sector strategies and interventions. In\r\ndoing so, CIADES seeks to address crucial social factors, including growing economic inequalities, stigma, and\r\nsocial disintegration, which have direct implications for mental well-being across the lifespan.\r\nMethodologically, CIADES employs a three-by-three matrix that interlinks three social determinants\u0097\r\nSocial Exclusion and Discrimination, Environmental Factors, and Employment\u0097with three priority populations:\r\nmigrants, older adults, and people with SMI (SMI). This matrix underpins interdisciplinary research lines,\r\nintegrating quantitative (e.g., epidemiological surveys, geospatial risk mapping), qualitative (e.g., multimodal\r\nand sensory ethnography, focus groups), and participatory methods. AI-driven analyses, such as natural\r\nlanguage processing for tracking stigma on social media, and economic evaluations that assess intervention\r\nfeasibility also feature prominently within the Center\u0092s approach.\r\nThe significance of this research lies in its focus on macro-structural drivers\u0097housing insecurity,\r\nworkplace discrimination, socio-environmental conflicts\u0097and how they contribute to mental health inequities.\r\nBy examining these intersecting challenges, CIADES will move beyond an exclusively clinical perspective to\r\npropose and evaluate, in close collaboration with MIDESO and MINSAL, evidence-based strategies that can be\r\nimplemented at multiple levels: local (community-based initiatives), regional (intersectoral policies), and\r\nnational (legislative reforms). This holistic orientation positions CIADES as a transformative force in Chile\u0092s\r\npublic policy on mental health. Once established, the Center expects to identify and integrate other social\r\ndeterminants and priority groups.\r\nThe Center\u0092s work will be guided by four Specific Objectives. First, Generate Evidence for Strategic\r\nInterventions and Policy Reforms involves collaborating with MIDESO and MINSAL to systematically examine\r\nsocio-structural determinants\u0097such as discrimination, environmental stressors, and employment\r\nvulnerabilities\u0097and generate robust evidence to inform and guide future interventions and policy actions.\r\nSecond, Methodological Development uses participatory and mixed-methods approaches, emphasizing\r\ncommunity involvement and local knowledge. Third, Capacity Building trains emerging researchers,\r\npolicymakers, and practitioners to apply the SDnH framework. Finally, Knowledge Dissemination and Policy\r\nAdvocacy entails translating findings into policy briefs, stakeholder workshops, and legislative\r\nrecommendations that foreground structural change and equitable access to the exercise of rights, and to\r\npolicies, programs and services.\r\nCIADES benefits from a multidisciplinary team involving principal and associate investigators with\r\nextensive track records in mental health, social sciences, environmental studies, and policy work. Their\r\ncollective experience includes leading large-scale epidemiological surveys, designing culturally relevant\r\ninterventions, and influencing legislative reforms. This breadth enables the Center to integrate cutting-edge\r\nmethods\u0097such as AI-driven stigma detection and geospatial modeling\u0097within a robust theoretical framework.\r\nBy drawing on a wide range of expertise, CIADES is uniquely positioned to undertake a comprehensive agenda\r\nthat links empirical research to transformative actions in policy and practice.\r\nCIADES anticipates having a significant impact at the national level by influencing discussions on the\r\ndesign, implementation, and evaluation of policies related to labor laws, anti-discrimination statutes,\r\ncommunity-oriented service models, environmental regulations, urban transformations, and other public\r\npolicies with an impact on mental health. In the short term, the center aims to increase recognition of the\r\nstructural factors that affect the mental health of different populations, factors that are often overlooked or\r\nignored due to the current emphasis on individual-focused approaches. Collaborating with communities,\r\nCIADES will co-design initiatives and pilot projects that serve as scalable case studies. These efforts will lead to\r\nthe production of policy briefs and guidelines, offering new frameworks to understand mental health challenges\r\nand proposing context-sensitive interventions. Over the medium to long term, CIADES aims to enhance\r\nintersectoral collaboration to drive structural-level interventions able to reduce mental health disparities\u0097\r\npositioning Chile as a regional leader in addressing mental health through a justice-based perspective.\r\nThe Center places a strong emphasis on capacity building and human capital formation as integral\r\ncomponents of its mission. Students from undergraduate to postgraduate levels will benefit from\r\ninterdisciplinary training in mental health, social epidemiology, qualitative methods, participatory methods and\r\ninclusive research, and implementation and dissemination science. This approach aims to nurture a new\r\ngeneration of scholars, practitioners, and other stakeholders equipped with the skills and knowledge necessary\r\nto advance the SDnH perspective. Furthermore, partnerships with leading international institutions, such as\r\nKing\u0092s College London and Columbia University, will facilitate knowledge exchange, foster global networks, and\r\nenhance CIADES\u0092 reach and credibility on an international scale.\r\nThrough proactive dissemination, outreach, and knowledge transfer, CIADES will engage with both\r\npublic and private sectors to drive actionable change. Dissemination channels include academic publications,\r\nopen-access materials, community forums, policy dialogues, and strategic communication through social media\r\nto ensure broader public penetration of the center's work.\r\nRegarding academic publications, CIADES is committed to publishing in high-impact international journals while\r\nalso recognizing the strategic importance of positioning itself within Latin American and national contexts by\r\ncontributing to academic journals in Spanish. Open-access materials will include the development of\r\nconceptual, methodological, and practical tools and guides, which will be freely available for public use.\r\nCommunity forums will serve both to share research findings and to identify emerging issues among the general\r\npopulation, while policy dialogues will aim to directly support and influence decision-making processes at the\r\npolicy level based on the center\u0092s research findings and experiences.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Patrocinante<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> CIN250054<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26958\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Centro de Investigaci\u00f3n y Acci\u00f3n en Determinaci\u00f3n Social y Salud Mental (Centro CIADES)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26958\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26958\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Mental health conditions and inequities in Chile have risen significantly over recent decades, fueled\r\nby factors such as social exclusion, precarious employment, and environmental challenges. In line with recent\r\nnational legislation and policy reforms, including the recently proposed Mental Health Law (2024,) there is\r\ngrowing recognition that these issues require not only expanded clinical services but also a deeper focus on the\r\nsocio-structural determinants of mental health (Breilh, 2023; Lund et al., 2018). The Centro de Investigaci\u00f3n y\r\nAcci\u00f3n en Determinaci\u00f3n Social y Salud Mental (Center for Research and Action in Social Determination and\r\nMental Health) or CIADES responds to this urgency by adopting a Latin American\u0096rooted Social Determination\r\nof Health (SDnH) framework, thereby situating mental health vulnerabilities and risks within broader historical,\r\neconomic, and political contexts.\r\nCIADES will work in close collaboration with the Ministry of Social Development and Family (MIDESO)\r\nand the Ministry of Health (MINSAL), to generate robust evidence and policy guidance to address the social\r\nfactors that affect and produce mental health problems beyond the individual. This collaboration ensures that\r\nthe Center\u0092s research advances academic knowledge and informs public-sector strategies and interventions. In\r\ndoing so, CIADES seeks to address crucial social factors, including growing economic inequalities, stigma, and\r\nsocial disintegration, which have direct implications for mental well-being across the lifespan.\r\nMethodologically, CIADES employs a three-by-three matrix that interlinks three social determinants\u0097\r\nSocial Exclusion and Discrimination, Environmental Factors, and Employment\u0097with three priority populations:\r\nmigrants, older adults, and people with SMI (SMI). This matrix underpins interdisciplinary research lines,\r\nintegrating quantitative (e.g., epidemiological surveys, geospatial risk mapping), qualitative (e.g., multimodal\r\nand sensory ethnography, focus groups), and participatory methods. AI-driven analyses, such as natural\r\nlanguage processing for tracking stigma on social media, and economic evaluations that assess intervention\r\nfeasibility also feature prominently within the Center\u0092s approach.\r\nThe significance of this research lies in its focus on macro-structural drivers\u0097housing insecurity,\r\nworkplace discrimination, socio-environmental conflicts\u0097and how they contribute to mental health inequities.\r\nBy examining these intersecting challenges, CIADES will move beyond an exclusively clinical perspective to\r\npropose and evaluate, in close collaboration with MIDESO and MINSAL, evidence-based strategies that can be\r\nimplemented at multiple levels: local (community-based initiatives), regional (intersectoral policies), and\r\nnational (legislative reforms). This holistic orientation positions CIADES as a transformative force in Chile\u0092s\r\npublic policy on mental health. Once established, the Center expects to identify and integrate other social\r\ndeterminants and priority groups.\r\nThe Center\u0092s work will be guided by four Specific Objectives. First, Generate Evidence for Strategic\r\nInterventions and Policy Reforms involves collaborating with MIDESO and MINSAL to systematically examine\r\nsocio-structural determinants\u0097such as discrimination, environmental stressors, and employment\r\nvulnerabilities\u0097and generate robust evidence to inform and guide future interventions and policy actions.\r\nSecond, Methodological Development uses participatory and mixed-methods approaches, emphasizing\r\ncommunity involvement and local knowledge. Third, Capacity Building trains emerging researchers,\r\npolicymakers, and practitioners to apply the SDnH framework. Finally, Knowledge Dissemination and Policy\r\nAdvocacy entails translating findings into policy briefs, stakeholder workshops, and legislative\r\nrecommendations that foreground structural change and equitable access to the exercise of rights, and to\r\npolicies, programs and services.\r\nCIADES benefits from a multidisciplinary team involving principal and associate investigators with\r\nextensive track records in mental health, social sciences, environmental studies, and policy work. Their\r\ncollective experience includes leading large-scale epidemiological surveys, designing culturally relevant\r\ninterventions, and influencing legislative reforms. This breadth enables the Center to integrate cutting-edge\r\nmethods\u0097such as AI-driven stigma detection and geospatial modeling\u0097within a robust theoretical framework.\r\nBy drawing on a wide range of expertise, CIADES is uniquely positioned to undertake a comprehensive agenda\r\nthat links empirical research to transformative actions in policy and practice.\r\nCIADES anticipates having a significant impact at the national level by influencing discussions on the\r\ndesign, implementation, and evaluation of policies related to labor laws, anti-discrimination statutes,\r\ncommunity-oriented service models, environmental regulations, urban transformations, and other public\r\npolicies with an impact on mental health. In the short term, the center aims to increase recognition of the\r\nstructural factors that affect the mental health of different populations, factors that are often overlooked or\r\nignored due to the current emphasis on individual-focused approaches. Collaborating with communities,\r\nCIADES will co-design initiatives and pilot projects that serve as scalable case studies. These efforts will lead to\r\nthe production of policy briefs and guidelines, offering new frameworks to understand mental health challenges\r\nand proposing context-sensitive interventions. Over the medium to long term, CIADES aims to enhance\r\nintersectoral collaboration to drive structural-level interventions able to reduce mental health disparities\u0097\r\npositioning Chile as a regional leader in addressing mental health through a justice-based perspective.\r\nThe Center places a strong emphasis on capacity building and human capital formation as integral\r\ncomponents of its mission. Students from undergraduate to postgraduate levels will benefit from\r\ninterdisciplinary training in mental health, social epidemiology, qualitative methods, participatory methods and\r\ninclusive research, and implementation and dissemination science. This approach aims to nurture a new\r\ngeneration of scholars, practitioners, and other stakeholders equipped with the skills and knowledge necessary\r\nto advance the SDnH perspective. Furthermore, partnerships with leading international institutions, such as\r\nKing\u0092s College London and Columbia University, will facilitate knowledge exchange, foster global networks, and\r\nenhance CIADES\u0092 reach and credibility on an international scale.\r\nThrough proactive dissemination, outreach, and knowledge transfer, CIADES will engage with both\r\npublic and private sectors to drive actionable change. Dissemination channels include academic publications,\r\nopen-access materials, community forums, policy dialogues, and strategic communication through social media\r\nto ensure broader public penetration of the center's work.\r\nRegarding academic publications, CIADES is committed to publishing in high-impact international journals while\r\nalso recognizing the strategic importance of positioning itself within Latin American and national contexts by\r\ncontributing to academic journals in Spanish. Open-access materials will include the development of\r\nconceptual, methodological, and practical tools and guides, which will be freely available for public use.\r\nCommunity forums will serve both to share research findings and to identify emerging issues among the general\r\npopulation, while policy dialogues will aim to directly support and influence decision-making processes at the\r\npolicy level based on the center\u0092s research findings and experiences.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2025 - Abril 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26738\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Observatorio Acoso Regi\u00f3n de O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26738\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26738\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Piloto de mapeo y espacializaci\u00f3n de experiencias de acoso en la Regi\u00f3n de O'Higgins[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2025 - Diciembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>University of Applied Sciences Emden\/Leer, Germany and Universidad de Valpara\u00edso, Chile<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26846\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Memorias y consecuencias transgeneracionales de violencia pol\u00edtica para la salud mental y social (Argentina, Chile, Grecia y Polonia)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26846\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26846\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La violencia sistem\u00e1tica desde el Estado ocurri\u00f3 en muchos pa\u00edses, incluyendo a Chile,\r\nArgentina, Polonia y Grecia. Las dictaduras militares en Chile (1973\u00961990), Argentina (1976-\r\n1983) y Grecia (1967-1974) produjeron violaciones sistem\u00e1ticas a los derechos humanos,\r\nincluyendo: desapariciones, torturas, ejecuciones y exilio. Aunque existen m\u00faltiples estudios\r\nsobre las v\u00edctimas directas, a\u00fan hay menos conocimiento sobre c\u00f3mo el impacto de estas\r\nexperiencias transforma la salud mental y social de las v\u00edctimas directas, sus hijos y nietos. Este\r\nestudio internacional busca contribuir a comprender mejor esta situaci\u00f3n, con el objetivo de explorar los mecanismos de transmisi\u00f3n intergeneracional de las memorias de la dictadura y sus efectos en la salud mental y social de los descendientes de v\u00edctimas directas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2025 - Abril 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27098\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Observatorio Acoso Regi\u00f3n de O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27098\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27098\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Piloto de mapeo y espacializaci\u00f3n de experiencias de acoso en la Regi\u00f3n de O'Higgins[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2025 - Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>IEEE RAS<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26103\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26103\" aria-expanded=\"false\" aria-controls=\"collapse-26103\">\n                                            IEEE RAS Technical Education Program\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26103\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26103\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Fondos para apoyar la realizacion de la Fourth Latin American Summer School on Robotics (LACORO 2025). La primera edici\u00f3n se realiz\u00f3 online en octubre de 2020; la segunda fue presencial en enero de 2023; la tercera 2024 en la Universidad de O'Higgins en Rancagua, Chile. La cuarta edici\u00f3n tendr\u00e1 lugar en diciembre de 2025 en la Universidad de O'Higgins. https:\/\/lacoro.org\/\r\n\r\nEsta Escuela de Verano beneficiar\u00e1 principalmente a Estudiantes y Acad\u00e9micos de las Am\u00e9ricas interesados en la Investigaci\u00f3n en Inteligencia Artificial aplicada a la Rob\u00f3tica. Nuestro objetivo es fomentar la colaboraci\u00f3n nacional y regional en esta \u00e1rea de investigaci\u00f3n. Para la primera edici\u00f3n, alcanzamos 241 inscripciones para actividades online de todo el mundo, y la segunda versi\u00f3n tuvo 166 inscripciones para actividades presenciales en enero de 2023, principalmente de Chile, M\u00e9xico, Argentina, Brasil y Uruguay.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2025 - Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>IEEE RAS<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26928\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26928\" aria-expanded=\"false\" aria-controls=\"collapse-26928\">\n                                            IEEE RAS Technical Education Program\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26928\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26928\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Fondos para apoyar la realizacion de la Fourth Latin American Summer School on Robotics (LACORO 2025). La primera edici\u00f3n se realiz\u00f3 online en octubre de 2020; la segunda fue presencial en enero de 2023; la tercera 2024 en la Universidad de O'Higgins en Rancagua, Chile. La cuarta edici\u00f3n tendr\u00e1 lugar en diciembre de 2025 en la Universidad de O'Higgins. https:\/\/lacoro.org\/\r\n\r\nEsta Escuela de Verano beneficiar\u00e1 principalmente a Estudiantes y Acad\u00e9micos de las Am\u00e9ricas interesados en la Investigaci\u00f3n en Inteligencia Artificial aplicada a la Rob\u00f3tica. Nuestro objetivo es fomentar la colaboraci\u00f3n nacional y regional en esta \u00e1rea de investigaci\u00f3n. Para la primera edici\u00f3n, alcanzamos 241 inscripciones para actividades online de todo el mundo, y la segunda versi\u00f3n tuvo 166 inscripciones para actividades presenciales en enero de 2023, principalmente de Chile, M\u00e9xico, Argentina, Brasil y Uruguay.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2025 - Noviembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Fundaci\u00f3n para la Innovaci\u00f3n Agraria - FIA<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26634\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            SaviaLab Regi\u00f3n de O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26634\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26634\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]SaviaLab promueve la innovaci\u00f3n temprana en j\u00f3venes rurales entre 15 y 18 a\u00f1os, de la mano de sus comunidades escolares y universidades regionales, a trav\u00e9s de una fase formativa y una fase concursable regional. SaviaLab se ejecuta en establecimientos t\u00e9cnicos profesionales, a trav\u00e9s de la incorporaci\u00f3n de una metodolog\u00eda para trabajar colaborativamente en la detecci\u00f3n de oportunidades de innovaci\u00f3n, que luego se transforman en soluciones pertinentes y relevantes para sus territorios.\r\n\r\nPara esto, la Fundaci\u00f3n ha coordinado un trabajo colaborativo con la Universidad de O'Higgins que se encargar\u00e1 de potenciar y asesorar el trabajo de los j\u00f3venes en las regi\u00f3n de O'Higgins.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidd del Pa\u00eds Vasco<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26739\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Cuidado parental y exposici\u00f3n temprana al alcohol: efectos sobre los niveles de ansiedad y la respuesta hacia el alcohol en la infancia y adolescencia de la rata.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26739\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26739\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las primeras etapas de la vida son cr\u00edticas para el desarrollo neuroconductual, y el entorno de crianza,\r\nespecialmente el cuidado parental, tiene una influencia clave (Ahern y Young, 2009). Investigaciones\r\nen humanos y en modelos animales, muestran que factores que alteran la conducta materna pueden\r\nincrementar el riesgo de consumo problem\u00e1tico de alcohol de la progenie, as\u00ed como aumentar sus\r\nconductas de ansiedad en la adultez (Francis y Kuhar 2008; Widom, 1995). Estudios experimentales\r\ncon animales han mostrado que manipulaciones como la separaci\u00f3n materna prolongada, aumentan la\r\nansiedad y los niveles de cortisol en sangre, mientras que disminuyen los niveles de oxitocina en\r\nmadres y sus cr\u00edas, generando mayor consumo de alcohol, especialmente en los machos (Baracz, et al.,\r\n2020; Nikolakopoulou, et al., 2021). Asimismo, se ha demostrado que variaciones en las estrategias de\r\ncuidado parental propias de cada especie pueden ser un factor protector o generador de situaciones de\r\nansiedad. Estudios en roedores muestran que un entorno de crianza enriquecido socialmente puede\r\nproteger frente a conductas de riesgo y consumo de sustancias (Pasquetta, et al., 2024; Ferreyra, et al.,\r\n2020).\r\nPor otra parte, estudios cl\u00ednicos y experimentales indican que la exposici\u00f3n prenatal al alcohol, durante\r\ntoda la gestaci\u00f3n o solo en su etapa final, incrementa el consumo de esta droga en la descendencia\r\n(Chotro et al, 2009; 2019; Gazta\u00f1aga et al, 2020). Este aumento se explica, por una parte, los efectos\r\nansiol\u00edticos del alcohol y la sensibilizaci\u00f3n del eje HPA (mayor ansiedad) y por otra parte, por un\r\nmecanismo de aprendizaje prenatal que asocia el olor y sabor del alcohol con sus efectos placenteros\r\n(Chotro et al, 2007; Gazta\u00f1aga et al, 2019). En estas respuestas tambi\u00e9n se ha observado diferencias\r\nsexuales en la adolescencia, siendo las hembras m\u00e1s sensibles que los machos a los efectos ansiol\u00edticos\r\ndel alcohol.\r\nEn conjunto, estas evidencias muestran que el entorno de crianza impacta directamente en la ansiedad\r\nmaterna y en el desarrollo emocional de la progenie, y que la exposici\u00f3n temprana al alcohol\r\nincrementa el riesgo de ansiedad y de consumo problem\u00e1tico de esta droga. Por lo que la combinaci\u00f3n\r\nde estos factores podr\u00eda tener efectos aditivos, aunque esta interacci\u00f3n a\u00fan no ha sido suficientemente\r\nestudiada. Dado que estas condiciones frecuentemente coexisten en contextos familiares, es prioritario\r\ninvestigar c\u00f3mo su combinaci\u00f3n influye en el desarrollo emocional y en el consumo de sustancias en la\r\ndescendencia, y si existen diferencias sexuales en estos efectos. Esto podr\u00eda abrir nuevas v\u00edas para\r\nintervenciones preventivas m\u00e1s eficaces.\r\nEl objetivo general de este proyecto consiste en analizar, en un modelo animal, la interacci\u00f3n entre el\r\nimpacto de las variaciones en el contexto de crianza y la exposici\u00f3n temprana al alcohol, sobre la\r\nconducta materna y los niveles de ansiedad de la madre. Como as\u00ed tambi\u00e9n sobre las conductas de\r\nansiedad y el consumo de alcohol en la progenie, tanto en machos como en hembras. Para abordar este\r\nobjetivo general, se han planificado dos series de experimentos con ratas, cada uno con su objetivo\r\nespec\u00edfico.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2025 - Diciembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26384\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Mujeres y salud ecosist\u00e9mica: fortaleciendo capacidades comunitarias y universitarias para la vigilancia ambiental de humedales en O\u0092Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26384\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26384\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La Regi\u00f3n de O\u0092Higgins cuenta con una red diversa de humedales que incluyen sistemas costeros, rurales,\r\ntemporales y artificiales. Estos ecosistemas cumplen un papel fundamental en la regulaci\u00f3n h\u00eddrica, el\r\nalmacenamiento de carbono, el soporte a la biodiversidad y el sustento de actividades econ\u00f3micas y\r\nculturales. Sin embargo, se encuentran bajo presi\u00f3n creciente debido a factores como la urbanizaci\u00f3n no\r\nplanificada, el vertido de aguas residuales, el cambio en el uso de suelo y los impactos del cambio clim\u00e1tico.\r\nEstos procesos generan deterioro de la calidad del agua, p\u00e9rdida de h\u00e1bitat y riesgos sanitarios asociados,\r\nincluyendo la proliferaci\u00f3n de cianobacterias productoras de toxinas y la presencia de pat\u00f3genos zoon\u00f3ticos.\r\nEn este contexto, la incorporaci\u00f3n de la perspectiva de g\u00e9nero en la vigilancia ambiental se vuelve crucial.\r\nLas mujeres de comunidades costeras y rurales poseen un conocimiento profundo del territorio, derivado de\r\nsu interacci\u00f3n cotidiana con el agua y los recursos naturales. Este saber local, que abarca desde la\r\nidentificaci\u00f3n de cambios estacionales en el humedal hasta el uso de plantas y productos naturales para el\r\ncuidado de la salud, es un activo valioso para el monitoreo ambiental. Sin embargo, las barreras\r\nestructurales y socioculturales limitan su participaci\u00f3n en espacios de toma de decisiones y en iniciativas de\r\nmonitoreo formal.\r\nEste proyecto propone una estrategia de fortalecimiento de capacidades para mujeres y estudiantes\r\nuniversitarios\/as en la vigilancia comunitaria de humedales, integrando herramientas simples de monitoreo\r\nde calidad de agua y biodiversidad, con un enfoque interdisciplinario que combina Medicina Veterinaria,\r\nTrabajo Social y Agroicultura Familiar Campesina (Farmacolog\u00eda de productos naturales). Se trabajar\u00e1 en dos\r\nhumedales piloto: Petrel, un sistema costero con influencia marina y alta presi\u00f3n tur\u00edstica, y San Jos\u00e9, un\r\nhumedal rural temporal vinculado a la agricultura familiar campesina. La elecci\u00f3n de estos sitios permite\r\nabordar realidades ecol\u00f3gicas y sociales contrastantes, garantizando que el protocolo de monitoreo\r\nresultante sea adaptable a diferentes contextos.\r\nLas actividades incluir\u00e1n un diagn\u00f3stico participativo de percepciones, barreras y oportunidades para la\r\nparticipaci\u00f3n de mujeres; talleres de capacitaci\u00f3n te\u00f3rico-pr\u00e1cticos; co-dise\u00f1o e implementaci\u00f3n de un\r\nprotocolo de monitoreo con participaci\u00f3n comunitaria; y difusi\u00f3n de resultados mediante un seminario\r\nabierto, y finalmente publicaciones. Como productos concretos se generar\u00e1 un protocolo de monitoreo\r\ncomunitario con enfoque de g\u00e9nero, material educativo validado por las comunidades y dos tesis de\r\npregrado asociadas al proyecto.\r\nEste enfoque no solo contribuir\u00e1 a visibilizar y valorar el aporte de las mujeres en la gesti\u00f3n ambiental, sino\r\nque tambi\u00e9n fortalecer\u00e1 la conexi\u00f3n entre la Universidad de O\u0092Higgins y el territorio, promoviendo una\r\ncultura de cuidado ambiental inclusiva, basada en la ciencia y el conocimiento local.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de La Rep\u00fablica Uruguay<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27099\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Migraci\u00f3n interna, despoblamiento, envejecimiento y brechas de bienestar en las peque\u00f1as localidades: Uruguay en el \u00faltimo medio siglo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27099\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27099\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Pregunta de investigaci\u00f3n: \u00bfcu\u00e1l ha sido el papel y consecuencias de la migraci\u00f3n interna de las \u00faltimas\r\n\u00bfD\u00e9cadas sobre las peque\u00f1as localidades?[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> N\u00ba 2025-03<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2025 - Noviembre 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Sociedad Chilena de Endocrinolog\u00eda y Diabetes<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26557\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Disfunci\u00f3n Pancre\u00e1tica y Muscular Asociada a la hepatoquina Fetuina-A en un Modelo Murino de Esteatohepatitis\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26557\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26557\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Disfunci\u00f3n Pancre\u00e1tica y Muscular Asociada a la hepatoquina Fetuina-A en un Modelo Murino de Esteatohepatitis[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26014\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Conocimientos 2030 Etapa 2\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26014\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26014\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las regiones de O\u0092Higgins y el Maule tienen una historia com\u00fan, caracter\u00edsticas y un\r\ndesarrollo social similar. Ambas regiones, ubicadas en el Valle Central chileno, comparten\r\nelementos culturales, s\u00edmbolos, historias y personajes que, su conjunto, reflejan la\r\nidentidad chilena. La historia de estos territorios incluye conocimiento diverso sobre\r\nnuestro pasado reciente y lejano en forma de relatos, pinturas, medios de transporte,\r\nmecanismos de comercializaci\u00f3n, oficios y manifestaciones culturales, que son comunes a\r\nellas. Debido a las importantes similitudes territoriales, humanas y productivas que poseen\r\nlas regiones de O\u0092Higgins y el Maule, es que sus universidades estatales proponen la\r\ninstitucionalizaci\u00f3n de un consorcio interuniversitario para fortalecer las Humanidades,\r\nArtes y Ciencias Sociales (HACS) en el Valle Central de Chile, transformando procesos\r\nacad\u00e9micos y generando instancias de participaci\u00f3n activa con la comunidad territorial.\r\nEste consorcio interuniversitario entre la Universidad de Talca y la Universidad de O\u0092Higgins\r\nse denomina \u0093Consorcio del Valle Central\u0094, en su af\u00e1n por ver representadas las realidades\r\ny conocimientos territoriales de la costa, del centro y de la cordillera de la VII y VI Regi\u00f3n.\r\nLa creaci\u00f3n del Consorcio Valle Central est\u00e1 sustentada en el Plan Estrat\u00e9gico para el\r\nFortalecimiento de las HACS, construido como producto de la etapa 1 de\r\nConocimientos2030. Este, a su vez, est\u00e1 basado en un diagn\u00f3stico exhaustivo que incluy\u00f3\r\nan\u00e1lisis interno, territorial (de cada provincia del Valle Central) y benchmarking con\r\ninstituciones de referencia. Como resultado, se identificaron una serie de dificultades en\r\nnuestras unidades que son relevantes para la transformaci\u00f3n de los procesos acad\u00e9micos.\r\nEntre ellas:\r\n\u0095 Rigidez de los programas formativos y uso de metodolog\u00edas encasilladas en las\r\ndisciplinas, que dificultan el an\u00e1lisis de la realidad social y p\u00fablica.\r\n\u0095 Limitada incorporaci\u00f3n de las complejidades del territorio a la formaci\u00f3n, afectando\r\nnegativamente a la relaci\u00f3n bidireccional y al desarrollo de iniciativas innovadoras.\r\n\u0095 Iniciativas acad\u00e9micas se acotan a fondos p\u00fablicos y muy competitivos, siendo\r\nexcepciones aquellos del sector privado o de inter\u00e9s p\u00fablico.\r\n\u0095 Desarrollo incipiente de la inter y transdisciplina (en adelante, ITD), e insuficiente\r\ntransferencia de conocimientos y tecnolog\u00edas.\r\n\u0095 Procesos de desarrollo acad\u00e9mico enfatizan el crecimiento individual, poco claros\r\npara acad\u00e9micos.as del \u00e1rea de las artes o con enfoque en ITD. Existen diferencias\r\nde g\u00e9nero favorables a hombres en jerarquizaci\u00f3n, publicaciones y proyectos\r\nobtenidos.\r\n\u0095 Gesti\u00f3n acad\u00e9mica desarticulada entre las unidades, observ\u00e1ndose repetici\u00f3n de\r\nprocesos de gesti\u00f3n entre las unidades participantes.\r\n\u0095 Los miembros de la comunidad indican percibir lo que denominan \u0093extractivismo\r\nacad\u00e9mico\u0094, una pr\u00e1ctica acad\u00e9mica en donde el v\u00ednculo con las comunidades\r\ntermina con la recogida de datos. Adem\u00e1s, el conocimiento universitario no es de\r\nf\u00e1cil acceso.\r\nEl an\u00e1lisis y discusi\u00f3n de las consecuencias de dichas limitaciones derivaron en el\r\nplanteamiento de propuestas, que buscan generar transformaci\u00f3n en nuestros procesos\r\nacad\u00e9micos, fomentando la flexibilidad curricular, la ITD, la generaci\u00f3n de conocimientos con atenci\u00f3n al territorio y la promoci\u00f3n de la equidad entre personas y la participaci\u00f3n\r\nfemenina en roles de liderazgo. Algunas de ellas son:\r\n1. Conformar un consorcio interuniversitario en HACS de las Universidades P\u00fablicas de\r\nlas Regiones VI y VII, cuya gobernanza colaborativa promueva transformaciones en\r\nlos procesos formativos, de investigaci\u00f3n y creaci\u00f3n, vinculaci\u00f3n con el medio (VcM)\r\ny gesti\u00f3n en ambas universidades. Posee sellos espec\u00edficos en fomento del\r\npatrimonio, de salud mental y bienestar, equidad de g\u00e9nero y derechos humanos y\r\npromueve la discusi\u00f3n y desarrollo de pol\u00edticas p\u00fablicas regionales y nacionales.\r\n2. Redise\u00f1ar carreras de pregrado HACS en cada universidad, flexibles, incorporando\r\nmetodolog\u00edas ITD y problem\u00e1ticas del Valle Central, formando as\u00ed competencias de\r\ntransferencia de conocimientos para la innovaci\u00f3n social y la pol\u00edtica p\u00fablica y\r\ncultural.\r\n3. Formular e implementar programas de estudio interuniversitarios, con un modelo\r\nequivalente a los pregrados redise\u00f1ados, con foco en formaci\u00f3n continua y\r\npostgrado.\r\n4. Construir micro-certificaciones al alero de los planes de estudio de pregrado,\r\npromoviendo la flexibilidad curricular y la innovaci\u00f3n para las profesiones del futuro.\r\n5. Crear una comisi\u00f3n paritaria de g\u00e9nero, ocupada de generaci\u00f3n consorciada de\r\npropuestas y seguimiento de datos para el logro de la equidad de g\u00e9nero, abierto a\r\nla comunidad universitaria y del Valle Central.\r\n6. Constituir equipos de investigaci\u00f3n\/creaci\u00f3n con foco ITD e interuniversitario,\r\nincorporando problem\u00e1ticas del Valle Central y promoviendo la discusi\u00f3n y\r\ngeneraci\u00f3n de pol\u00edticas p\u00fablicas en las \u00e1reas de desarrollo.\r\n7. Habilitar un espacio f\u00edsico independiente a las facultades, donde las personas que se\r\nadscriben desarrollen ITD de manera abierta y colaborativa con otros acad\u00e9micos,\r\nestudiantes y\/o miembros de la sociedad civil.\r\n8. Creaci\u00f3n de una gobernanza que involucre a la comunidad acad\u00e9mica, estudiantil y\r\nde la comuna, para la ejecuci\u00f3n y asesor\u00eda de las acciones programadas, enfatizando\r\nlos sellos del proyecto y acercando las propuestas al desarrollo y logro de pol\u00edticas\r\np\u00fablicas.\r\n9. Presentar a las autoridades superiores universitarias un perfil de desarrollo de\r\nacad\u00e9micas.os HACS con \u00e9nfasis en indicadores para la jerarquizaci\u00f3n,\r\nhomologando con ello las trayectorias acad\u00e9micas en todas las disciplinas\r\nuniversitarias (especialmente artes) incorporando enfoque ITD.\r\n10.Promover la democratizaci\u00f3n del conocimiento a partir del uso de herramientas de\r\nciencia abierta, incorpor\u00e1ndolas en el desarrollo de la formaci\u00f3n, y a trav\u00e9s del uso\r\nde repositorios para el almacenamiento de informaci\u00f3n de todas las disciplinas\r\nHACS.\r\nConsideramos que los conocimientos de nuestros territorios son una oportunidad para el\r\nmejoramiento de nuestros planes de formaci\u00f3n, as\u00ed como para proponer otros nuevos que\r\narticulen las capacidades de los planteles universitarios. Esta propuesta plantea que es\r\nprioritaria la capacitaci\u00f3n docente en estrategias ITD, permitiendo con ello el abordaje de problemas relevantes para el territorio desde una perspectiva amplia. Todo lo anterior,\r\npermitir\u00e1 formar profesionales capacitados para desarrollarse en entornos complejos.\r\nEn el campo de la investigaci\u00f3n la propuesta considera la creaci\u00f3n de grupos de trabajo\r\nITD en tem\u00e1ticas espec\u00edficas de desarrollo para las HACS, enfatizando los temas de\r\nPatrimonio, Salud Mental y Bienestar, y Liderazgo de Mujeres. Estos grupos deber\u00e1n\r\npromover el liderazgo de mujeres en sus propuestas, relacionarse con su espacio de inter\u00e9s\r\ne involucrar a los actores sociales de manera activa y rec\u00edproca. El objetivo es crear, en 10\r\na\u00f1os, grupos de referencia nacional en investigaci\u00f3n b\u00e1sica, aplicada y art\u00edstica con base\r\nen ITD permitiendo, as\u00ed, sustentabilidad de las estrategias de desarrollo m\u00e1s all\u00e1 del\r\nperiodo de financiaci\u00f3n. Construir un camino de desarrollo acad\u00e9mico para las HACS,\r\nbasado en ITD y con especial atenci\u00f3n a las artes permitir\u00e1 mayor equidad disciplinar en\r\neste proceso y orientaci\u00f3n para el desarrollo, aumentando as\u00ed el valor de los conocimientos\r\ncient\u00edficos, creativos y tradicionales para la instituci\u00f3n.\r\nPretendemos construir una estrategia de VcM sustentada en conocimiento cient\u00edfico y\r\ncreativo, promoviendo con ello la innovaci\u00f3n, la transferencia y el escalamiento de\r\nproductos, en donde participa de manera activa la comunidad no acad\u00e9mica de nuestros\r\nterritorios. Es nuestro inter\u00e9s democratizar el conocimiento y abrirlo a nuestras\r\ncomunidades a trav\u00e9s de mecanismos de ciencia abierta y, por \u00faltimo, una gobernanza\r\neficiente para articular nuestros objetivos y metas, desarrollando herramientas de\r\ndiscusi\u00f3n colaborativa, seguimiento y evaluaci\u00f3n de impacto para la mejora continua.\r\nEl horizonte de desarrollo de nuestras iniciativas es de diez a\u00f1os, comprometiendo al sexto\r\na\u00f1o de ejecuci\u00f3n una serie de acciones que involucran, en ambas regiones, un\r\nacercamiento de cada instituci\u00f3n a su espacio de influencia y colaboraci\u00f3n entre ellas. As\u00ed\r\nmismo, esperamos constituir un espacio consorciado que promueve una formaci\u00f3n\r\nprofesional sensible a las necesidades del entorno y cuyos estudiantes poseen\r\ncompetencias para atenderlas en colaboraci\u00f3n con sus habitantes; que capacita a\r\nacad\u00e9micos y profesionales en mecanismos de promoci\u00f3n de la ITD; que participa en la\r\ndiscusi\u00f3n y generaci\u00f3n de pol\u00edticas p\u00fablicas; que desarrolla conocimiento ITD a trav\u00e9s de\r\ngrupos cuya investigaci\u00f3n se aplica a temas espec\u00edficos, siendo referentes a nivel nacional;\r\nque se relaciona con el entorno de manera cooperativa y bidireccional, cuyos conocimientos\r\nson la base de la innovaci\u00f3n y la transferencia. Y, por \u00faltimo, un espacio que promueve la\r\nequidad de g\u00e9nero, la participaci\u00f3n de mujeres en espacios de liderazgo y la participaci\u00f3n\r\nsocial de nuestros territorios.\r\nFinalmente, podremos configurarnos como un consorcio universitario con gran presencia\r\nen sus regiones y que desarrolle un trabajo virtuoso con diferentes actores del mundo\r\nuniversitario y de la sociedad civil, quienes asesorar\u00e1n nuestro trabajo de manera que\r\natiendan a pol\u00edticas p\u00fablicas y necesidades de los territorios.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26068\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Conocimientos 2030 Etapa 2\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26068\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26068\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las regiones de O\u0092Higgins y el Maule tienen una historia com\u00fan, caracter\u00edsticas y un\r\ndesarrollo social similar. Ambas regiones, ubicadas en el Valle Central chileno, comparten\r\nelementos culturales, s\u00edmbolos, historias y personajes que, su conjunto, reflejan la\r\nidentidad chilena. La historia de estos territorios incluye conocimiento diverso sobre\r\nnuestro pasado reciente y lejano en forma de relatos, pinturas, medios de transporte,\r\nmecanismos de comercializaci\u00f3n, oficios y manifestaciones culturales, que son comunes a\r\nellas. Debido a las importantes similitudes territoriales, humanas y productivas que poseen\r\nlas regiones de O\u0092Higgins y el Maule, es que sus universidades estatales proponen la\r\ninstitucionalizaci\u00f3n de un consorcio interuniversitario para fortalecer las Humanidades,\r\nArtes y Ciencias Sociales (HACS) en el Valle Central de Chile, transformando procesos\r\nacad\u00e9micos y generando instancias de participaci\u00f3n activa con la comunidad territorial.\r\nEste consorcio interuniversitario entre la Universidad de Talca y la Universidad de O\u0092Higgins\r\nse denomina \u0093Consorcio del Valle Central\u0094, en su af\u00e1n por ver representadas las realidades\r\ny conocimientos territoriales de la costa, del centro y de la cordillera de la VII y VI Regi\u00f3n.\r\nLa creaci\u00f3n del Consorcio Valle Central est\u00e1 sustentada en el Plan Estrat\u00e9gico para el\r\nFortalecimiento de las HACS, construido como producto de la etapa 1 de\r\nConocimientos2030. Este, a su vez, est\u00e1 basado en un diagn\u00f3stico exhaustivo que incluy\u00f3\r\nan\u00e1lisis interno, territorial (de cada provincia del Valle Central) y benchmarking con\r\ninstituciones de referencia. Como resultado, se identificaron una serie de dificultades en\r\nnuestras unidades que son relevantes para la transformaci\u00f3n de los procesos acad\u00e9micos.\r\nEntre ellas:\r\n\u0095 Rigidez de los programas formativos y uso de metodolog\u00edas encasilladas en las\r\ndisciplinas, que dificultan el an\u00e1lisis de la realidad social y p\u00fablica.\r\n\u0095 Limitada incorporaci\u00f3n de las complejidades del territorio a la formaci\u00f3n, afectando\r\nnegativamente a la relaci\u00f3n bidireccional y al desarrollo de iniciativas innovadoras.\r\n\u0095 Iniciativas acad\u00e9micas se acotan a fondos p\u00fablicos y muy competitivos, siendo\r\nexcepciones aquellos del sector privado o de inter\u00e9s p\u00fablico.\r\n\u0095 Desarrollo incipiente de la inter y transdisciplina (en adelante, ITD), e insuficiente\r\ntransferencia de conocimientos y tecnolog\u00edas.\r\n\u0095 Procesos de desarrollo acad\u00e9mico enfatizan el crecimiento individual, poco claros\r\npara acad\u00e9micos.as del \u00e1rea de las artes o con enfoque en ITD. Existen diferencias\r\nde g\u00e9nero favorables a hombres en jerarquizaci\u00f3n, publicaciones y proyectos\r\nobtenidos.\r\n\u0095 Gesti\u00f3n acad\u00e9mica desarticulada entre las unidades, observ\u00e1ndose repetici\u00f3n de\r\nprocesos de gesti\u00f3n entre las unidades participantes.\r\n\u0095 Los miembros de la comunidad indican percibir lo que denominan \u0093extractivismo\r\nacad\u00e9mico\u0094, una pr\u00e1ctica acad\u00e9mica en donde el v\u00ednculo con las comunidades\r\ntermina con la recogida de datos. Adem\u00e1s, el conocimiento universitario no es de\r\nf\u00e1cil acceso.\r\nEl an\u00e1lisis y discusi\u00f3n de las consecuencias de dichas limitaciones derivaron en el\r\nplanteamiento de propuestas, que buscan generar transformaci\u00f3n en nuestros procesos\r\nacad\u00e9micos, fomentando la flexibilidad curricular, la ITD, la generaci\u00f3n de conocimientos con atenci\u00f3n al territorio y la promoci\u00f3n de la equidad entre personas y la participaci\u00f3n\r\nfemenina en roles de liderazgo. Algunas de ellas son:\r\n1. Conformar un consorcio interuniversitario en HACS de las Universidades P\u00fablicas de\r\nlas Regiones VI y VII, cuya gobernanza colaborativa promueva transformaciones en\r\nlos procesos formativos, de investigaci\u00f3n y creaci\u00f3n, vinculaci\u00f3n con el medio (VcM)\r\ny gesti\u00f3n en ambas universidades. Posee sellos espec\u00edficos en fomento del\r\npatrimonio, de salud mental y bienestar, equidad de g\u00e9nero y derechos humanos y\r\npromueve la discusi\u00f3n y desarrollo de pol\u00edticas p\u00fablicas regionales y nacionales.\r\n2. Redise\u00f1ar carreras de pregrado HACS en cada universidad, flexibles, incorporando\r\nmetodolog\u00edas ITD y problem\u00e1ticas del Valle Central, formando as\u00ed competencias de\r\ntransferencia de conocimientos para la innovaci\u00f3n social y la pol\u00edtica p\u00fablica y\r\ncultural.\r\n3. Formular e implementar programas de estudio interuniversitarios, con un modelo\r\nequivalente a los pregrados redise\u00f1ados, con foco en formaci\u00f3n continua y\r\npostgrado.\r\n4. Construir micro-certificaciones al alero de los planes de estudio de pregrado,\r\npromoviendo la flexibilidad curricular y la innovaci\u00f3n para las profesiones del futuro.\r\n5. Crear una comisi\u00f3n paritaria de g\u00e9nero, ocupada de generaci\u00f3n consorciada de\r\npropuestas y seguimiento de datos para el logro de la equidad de g\u00e9nero, abierto a\r\nla comunidad universitaria y del Valle Central.\r\n6. Constituir equipos de investigaci\u00f3n\/creaci\u00f3n con foco ITD e interuniversitario,\r\nincorporando problem\u00e1ticas del Valle Central y promoviendo la discusi\u00f3n y\r\ngeneraci\u00f3n de pol\u00edticas p\u00fablicas en las \u00e1reas de desarrollo.\r\n7. Habilitar un espacio f\u00edsico independiente a las facultades, donde las personas que se\r\nadscriben desarrollen ITD de manera abierta y colaborativa con otros acad\u00e9micos,\r\nestudiantes y\/o miembros de la sociedad civil.\r\n8. Creaci\u00f3n de una gobernanza que involucre a la comunidad acad\u00e9mica, estudiantil y\r\nde la comuna, para la ejecuci\u00f3n y asesor\u00eda de las acciones programadas, enfatizando\r\nlos sellos del proyecto y acercando las propuestas al desarrollo y logro de pol\u00edticas\r\np\u00fablicas.\r\n9. Presentar a las autoridades superiores universitarias un perfil de desarrollo de\r\nacad\u00e9micas.os HACS con \u00e9nfasis en indicadores para la jerarquizaci\u00f3n,\r\nhomologando con ello las trayectorias acad\u00e9micas en todas las disciplinas\r\nuniversitarias (especialmente artes) incorporando enfoque ITD.\r\n10.Promover la democratizaci\u00f3n del conocimiento a partir del uso de herramientas de\r\nciencia abierta, incorpor\u00e1ndolas en el desarrollo de la formaci\u00f3n, y a trav\u00e9s del uso\r\nde repositorios para el almacenamiento de informaci\u00f3n de todas las disciplinas\r\nHACS.\r\nConsideramos que los conocimientos de nuestros territorios son una oportunidad para el\r\nmejoramiento de nuestros planes de formaci\u00f3n, as\u00ed como para proponer otros nuevos que\r\narticulen las capacidades de los planteles universitarios. Esta propuesta plantea que es\r\nprioritaria la capacitaci\u00f3n docente en estrategias ITD, permitiendo con ello el abordaje de problemas relevantes para el territorio desde una perspectiva amplia. Todo lo anterior,\r\npermitir\u00e1 formar profesionales capacitados para desarrollarse en entornos complejos.\r\nEn el campo de la investigaci\u00f3n la propuesta considera la creaci\u00f3n de grupos de trabajo\r\nITD en tem\u00e1ticas espec\u00edficas de desarrollo para las HACS, enfatizando los temas de\r\nPatrimonio, Salud Mental y Bienestar, y Liderazgo de Mujeres. Estos grupos deber\u00e1n\r\npromover el liderazgo de mujeres en sus propuestas, relacionarse con su espacio de inter\u00e9s\r\ne involucrar a los actores sociales de manera activa y rec\u00edproca. El objetivo es crear, en 10\r\na\u00f1os, grupos de referencia nacional en investigaci\u00f3n b\u00e1sica, aplicada y art\u00edstica con base\r\nen ITD permitiendo, as\u00ed, sustentabilidad de las estrategias de desarrollo m\u00e1s all\u00e1 del\r\nperiodo de financiaci\u00f3n. Construir un camino de desarrollo acad\u00e9mico para las HACS,\r\nbasado en ITD y con especial atenci\u00f3n a las artes permitir\u00e1 mayor equidad disciplinar en\r\neste proceso y orientaci\u00f3n para el desarrollo, aumentando as\u00ed el valor de los conocimientos\r\ncient\u00edficos, creativos y tradicionales para la instituci\u00f3n.\r\nPretendemos construir una estrategia de VcM sustentada en conocimiento cient\u00edfico y\r\ncreativo, promoviendo con ello la innovaci\u00f3n, la transferencia y el escalamiento de\r\nproductos, en donde participa de manera activa la comunidad no acad\u00e9mica de nuestros\r\nterritorios. Es nuestro inter\u00e9s democratizar el conocimiento y abrirlo a nuestras\r\ncomunidades a trav\u00e9s de mecanismos de ciencia abierta y, por \u00faltimo, una gobernanza\r\neficiente para articular nuestros objetivos y metas, desarrollando herramientas de\r\ndiscusi\u00f3n colaborativa, seguimiento y evaluaci\u00f3n de impacto para la mejora continua.\r\nEl horizonte de desarrollo de nuestras iniciativas es de diez a\u00f1os, comprometiendo al sexto\r\na\u00f1o de ejecuci\u00f3n una serie de acciones que involucran, en ambas regiones, un\r\nacercamiento de cada instituci\u00f3n a su espacio de influencia y colaboraci\u00f3n entre ellas. As\u00ed\r\nmismo, esperamos constituir un espacio consorciado que promueve una formaci\u00f3n\r\nprofesional sensible a las necesidades del entorno y cuyos estudiantes poseen\r\ncompetencias para atenderlas en colaboraci\u00f3n con sus habitantes; que capacita a\r\nacad\u00e9micos y profesionales en mecanismos de promoci\u00f3n de la ITD; que participa en la\r\ndiscusi\u00f3n y generaci\u00f3n de pol\u00edticas p\u00fablicas; que desarrolla conocimiento ITD a trav\u00e9s de\r\ngrupos cuya investigaci\u00f3n se aplica a temas espec\u00edficos, siendo referentes a nivel nacional;\r\nque se relaciona con el entorno de manera cooperativa y bidireccional, cuyos conocimientos\r\nson la base de la innovaci\u00f3n y la transferencia. Y, por \u00faltimo, un espacio que promueve la\r\nequidad de g\u00e9nero, la participaci\u00f3n de mujeres en espacios de liderazgo y la participaci\u00f3n\r\nsocial de nuestros territorios.\r\nFinalmente, podremos configurarnos como un consorcio universitario con gran presencia\r\nen sus regiones y que desarrolle un trabajo virtuoso con diferentes actores del mundo\r\nuniversitario y de la sociedad civil, quienes asesorar\u00e1n nuestro trabajo de manera que\r\natiendan a pol\u00edticas p\u00fablicas y necesidades de los territorios.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2025 - Septiembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26069\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26069\" aria-expanded=\"false\" aria-controls=\"collapse-26069\">\n                                            Congreso Literatura, Artes y Educaci\u00f3n: Narrativa y Paisajes\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26069\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26069\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Congreso nacional con participaci\u00f3n de Universidades de Santiago, Talca, Temuco, Curic\u00f3.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26083\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Conocimientos 2030 Etapa 2\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26083\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26083\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las regiones de O\u0092Higgins y el Maule tienen una historia com\u00fan, caracter\u00edsticas y un\r\ndesarrollo social similar. Ambas regiones, ubicadas en el Valle Central chileno, comparten\r\nelementos culturales, s\u00edmbolos, historias y personajes que, su conjunto, reflejan la\r\nidentidad chilena. La historia de estos territorios incluye conocimiento diverso sobre\r\nnuestro pasado reciente y lejano en forma de relatos, pinturas, medios de transporte,\r\nmecanismos de comercializaci\u00f3n, oficios y manifestaciones culturales, que son comunes a\r\nellas. Debido a las importantes similitudes territoriales, humanas y productivas que poseen\r\nlas regiones de O\u0092Higgins y el Maule, es que sus universidades estatales proponen la\r\ninstitucionalizaci\u00f3n de un consorcio interuniversitario para fortalecer las Humanidades,\r\nArtes y Ciencias Sociales (HACS) en el Valle Central de Chile, transformando procesos\r\nacad\u00e9micos y generando instancias de participaci\u00f3n activa con la comunidad territorial.\r\nEste consorcio interuniversitario entre la Universidad de Talca y la Universidad de O\u0092Higgins\r\nse denomina \u0093Consorcio del Valle Central\u0094, en su af\u00e1n por ver representadas las realidades\r\ny conocimientos territoriales de la costa, del centro y de la cordillera de la VII y VI Regi\u00f3n.\r\nLa creaci\u00f3n del Consorcio Valle Central est\u00e1 sustentada en el Plan Estrat\u00e9gico para el\r\nFortalecimiento de las HACS, construido como producto de la etapa 1 de\r\nConocimientos2030. Este, a su vez, est\u00e1 basado en un diagn\u00f3stico exhaustivo que incluy\u00f3\r\nan\u00e1lisis interno, territorial (de cada provincia del Valle Central) y benchmarking con\r\ninstituciones de referencia. Como resultado, se identificaron una serie de dificultades en\r\nnuestras unidades que son relevantes para la transformaci\u00f3n de los procesos acad\u00e9micos.\r\nEntre ellas:\r\n\u0095 Rigidez de los programas formativos y uso de metodolog\u00edas encasilladas en las\r\ndisciplinas, que dificultan el an\u00e1lisis de la realidad social y p\u00fablica.\r\n\u0095 Limitada incorporaci\u00f3n de las complejidades del territorio a la formaci\u00f3n, afectando\r\nnegativamente a la relaci\u00f3n bidireccional y al desarrollo de iniciativas innovadoras.\r\n\u0095 Iniciativas acad\u00e9micas se acotan a fondos p\u00fablicos y muy competitivos, siendo\r\nexcepciones aquellos del sector privado o de inter\u00e9s p\u00fablico.\r\n\u0095 Desarrollo incipiente de la inter y transdisciplina (en adelante, ITD), e insuficiente\r\ntransferencia de conocimientos y tecnolog\u00edas.\r\n\u0095 Procesos de desarrollo acad\u00e9mico enfatizan el crecimiento individual, poco claros\r\npara acad\u00e9micos.as del \u00e1rea de las artes o con enfoque en ITD. Existen diferencias\r\nde g\u00e9nero favorables a hombres en jerarquizaci\u00f3n, publicaciones y proyectos\r\nobtenidos.\r\n\u0095 Gesti\u00f3n acad\u00e9mica desarticulada entre las unidades, observ\u00e1ndose repetici\u00f3n de\r\nprocesos de gesti\u00f3n entre las unidades participantes.\r\n\u0095 Los miembros de la comunidad indican percibir lo que denominan \u0093extractivismo\r\nacad\u00e9mico\u0094, una pr\u00e1ctica acad\u00e9mica en donde el v\u00ednculo con las comunidades\r\ntermina con la recogida de datos. Adem\u00e1s, el conocimiento universitario no es de\r\nf\u00e1cil acceso.\r\nEl an\u00e1lisis y discusi\u00f3n de las consecuencias de dichas limitaciones derivaron en el\r\nplanteamiento de propuestas, que buscan generar transformaci\u00f3n en nuestros procesos\r\nacad\u00e9micos, fomentando la flexibilidad curricular, la ITD, la generaci\u00f3n de conocimientos con atenci\u00f3n al territorio y la promoci\u00f3n de la equidad entre personas y la participaci\u00f3n\r\nfemenina en roles de liderazgo. Algunas de ellas son:\r\n1. Conformar un consorcio interuniversitario en HACS de las Universidades P\u00fablicas de\r\nlas Regiones VI y VII, cuya gobernanza colaborativa promueva transformaciones en\r\nlos procesos formativos, de investigaci\u00f3n y creaci\u00f3n, vinculaci\u00f3n con el medio (VcM)\r\ny gesti\u00f3n en ambas universidades. Posee sellos espec\u00edficos en fomento del\r\npatrimonio, de salud mental y bienestar, equidad de g\u00e9nero y derechos humanos y\r\npromueve la discusi\u00f3n y desarrollo de pol\u00edticas p\u00fablicas regionales y nacionales.\r\n2. Redise\u00f1ar carreras de pregrado HACS en cada universidad, flexibles, incorporando\r\nmetodolog\u00edas ITD y problem\u00e1ticas del Valle Central, formando as\u00ed competencias de\r\ntransferencia de conocimientos para la innovaci\u00f3n social y la pol\u00edtica p\u00fablica y\r\ncultural.\r\n3. Formular e implementar programas de estudio interuniversitarios, con un modelo\r\nequivalente a los pregrados redise\u00f1ados, con foco en formaci\u00f3n continua y\r\npostgrado.\r\n4. Construir micro-certificaciones al alero de los planes de estudio de pregrado,\r\npromoviendo la flexibilidad curricular y la innovaci\u00f3n para las profesiones del futuro.\r\n5. Crear una comisi\u00f3n paritaria de g\u00e9nero, ocupada de generaci\u00f3n consorciada de\r\npropuestas y seguimiento de datos para el logro de la equidad de g\u00e9nero, abierto a\r\nla comunidad universitaria y del Valle Central.\r\n6. Constituir equipos de investigaci\u00f3n\/creaci\u00f3n con foco ITD e interuniversitario,\r\nincorporando problem\u00e1ticas del Valle Central y promoviendo la discusi\u00f3n y\r\ngeneraci\u00f3n de pol\u00edticas p\u00fablicas en las \u00e1reas de desarrollo.\r\n7. Habilitar un espacio f\u00edsico independiente a las facultades, donde las personas que se\r\nadscriben desarrollen ITD de manera abierta y colaborativa con otros acad\u00e9micos,\r\nestudiantes y\/o miembros de la sociedad civil.\r\n8. Creaci\u00f3n de una gobernanza que involucre a la comunidad acad\u00e9mica, estudiantil y\r\nde la comuna, para la ejecuci\u00f3n y asesor\u00eda de las acciones programadas, enfatizando\r\nlos sellos del proyecto y acercando las propuestas al desarrollo y logro de pol\u00edticas\r\np\u00fablicas.\r\n9. Presentar a las autoridades superiores universitarias un perfil de desarrollo de\r\nacad\u00e9micas.os HACS con \u00e9nfasis en indicadores para la jerarquizaci\u00f3n,\r\nhomologando con ello las trayectorias acad\u00e9micas en todas las disciplinas\r\nuniversitarias (especialmente artes) incorporando enfoque ITD.\r\n10.Promover la democratizaci\u00f3n del conocimiento a partir del uso de herramientas de\r\nciencia abierta, incorpor\u00e1ndolas en el desarrollo de la formaci\u00f3n, y a trav\u00e9s del uso\r\nde repositorios para el almacenamiento de informaci\u00f3n de todas las disciplinas\r\nHACS.\r\nConsideramos que los conocimientos de nuestros territorios son una oportunidad para el\r\nmejoramiento de nuestros planes de formaci\u00f3n, as\u00ed como para proponer otros nuevos que\r\narticulen las capacidades de los planteles universitarios. Esta propuesta plantea que es\r\nprioritaria la capacitaci\u00f3n docente en estrategias ITD, permitiendo con ello el abordaje de problemas relevantes para el territorio desde una perspectiva amplia. Todo lo anterior,\r\npermitir\u00e1 formar profesionales capacitados para desarrollarse en entornos complejos.\r\nEn el campo de la investigaci\u00f3n la propuesta considera la creaci\u00f3n de grupos de trabajo\r\nITD en tem\u00e1ticas espec\u00edficas de desarrollo para las HACS, enfatizando los temas de\r\nPatrimonio, Salud Mental y Bienestar, y Liderazgo de Mujeres. Estos grupos deber\u00e1n\r\npromover el liderazgo de mujeres en sus propuestas, relacionarse con su espacio de inter\u00e9s\r\ne involucrar a los actores sociales de manera activa y rec\u00edproca. El objetivo es crear, en 10\r\na\u00f1os, grupos de referencia nacional en investigaci\u00f3n b\u00e1sica, aplicada y art\u00edstica con base\r\nen ITD permitiendo, as\u00ed, sustentabilidad de las estrategias de desarrollo m\u00e1s all\u00e1 del\r\nperiodo de financiaci\u00f3n. Construir un camino de desarrollo acad\u00e9mico para las HACS,\r\nbasado en ITD y con especial atenci\u00f3n a las artes permitir\u00e1 mayor equidad disciplinar en\r\neste proceso y orientaci\u00f3n para el desarrollo, aumentando as\u00ed el valor de los conocimientos\r\ncient\u00edficos, creativos y tradicionales para la instituci\u00f3n.\r\nPretendemos construir una estrategia de VcM sustentada en conocimiento cient\u00edfico y\r\ncreativo, promoviendo con ello la innovaci\u00f3n, la transferencia y el escalamiento de\r\nproductos, en donde participa de manera activa la comunidad no acad\u00e9mica de nuestros\r\nterritorios. Es nuestro inter\u00e9s democratizar el conocimiento y abrirlo a nuestras\r\ncomunidades a trav\u00e9s de mecanismos de ciencia abierta y, por \u00faltimo, una gobernanza\r\neficiente para articular nuestros objetivos y metas, desarrollando herramientas de\r\ndiscusi\u00f3n colaborativa, seguimiento y evaluaci\u00f3n de impacto para la mejora continua.\r\nEl horizonte de desarrollo de nuestras iniciativas es de diez a\u00f1os, comprometiendo al sexto\r\na\u00f1o de ejecuci\u00f3n una serie de acciones que involucran, en ambas regiones, un\r\nacercamiento de cada instituci\u00f3n a su espacio de influencia y colaboraci\u00f3n entre ellas. As\u00ed\r\nmismo, esperamos constituir un espacio consorciado que promueve una formaci\u00f3n\r\nprofesional sensible a las necesidades del entorno y cuyos estudiantes poseen\r\ncompetencias para atenderlas en colaboraci\u00f3n con sus habitantes; que capacita a\r\nacad\u00e9micos y profesionales en mecanismos de promoci\u00f3n de la ITD; que participa en la\r\ndiscusi\u00f3n y generaci\u00f3n de pol\u00edticas p\u00fablicas; que desarrolla conocimiento ITD a trav\u00e9s de\r\ngrupos cuya investigaci\u00f3n se aplica a temas espec\u00edficos, siendo referentes a nivel nacional;\r\nque se relaciona con el entorno de manera cooperativa y bidireccional, cuyos conocimientos\r\nson la base de la innovaci\u00f3n y la transferencia. Y, por \u00faltimo, un espacio que promueve la\r\nequidad de g\u00e9nero, la participaci\u00f3n de mujeres en espacios de liderazgo y la participaci\u00f3n\r\nsocial de nuestros territorios.\r\nFinalmente, podremos configurarnos como un consorcio universitario con gran presencia\r\nen sus regiones y que desarrolle un trabajo virtuoso con diferentes actores del mundo\r\nuniversitario y de la sociedad civil, quienes asesorar\u00e1n nuestro trabajo de manera que\r\natiendan a pol\u00edticas p\u00fablicas y necesidades de los territorios.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26110\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Conocimientos 2030 Etapa 2\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26110\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26110\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las regiones de O\u0092Higgins y el Maule tienen una historia com\u00fan, caracter\u00edsticas y un\r\ndesarrollo social similar. Ambas regiones, ubicadas en el Valle Central chileno, comparten\r\nelementos culturales, s\u00edmbolos, historias y personajes que, su conjunto, reflejan la\r\nidentidad chilena. La historia de estos territorios incluye conocimiento diverso sobre\r\nnuestro pasado reciente y lejano en forma de relatos, pinturas, medios de transporte,\r\nmecanismos de comercializaci\u00f3n, oficios y manifestaciones culturales, que son comunes a\r\nellas. Debido a las importantes similitudes territoriales, humanas y productivas que poseen\r\nlas regiones de O\u0092Higgins y el Maule, es que sus universidades estatales proponen la\r\ninstitucionalizaci\u00f3n de un consorcio interuniversitario para fortalecer las Humanidades,\r\nArtes y Ciencias Sociales (HACS) en el Valle Central de Chile, transformando procesos\r\nacad\u00e9micos y generando instancias de participaci\u00f3n activa con la comunidad territorial.\r\nEste consorcio interuniversitario entre la Universidad de Talca y la Universidad de O\u0092Higgins\r\nse denomina \u0093Consorcio del Valle Central\u0094, en su af\u00e1n por ver representadas las realidades\r\ny conocimientos territoriales de la costa, del centro y de la cordillera de la VII y VI Regi\u00f3n.\r\nLa creaci\u00f3n del Consorcio Valle Central est\u00e1 sustentada en el Plan Estrat\u00e9gico para el\r\nFortalecimiento de las HACS, construido como producto de la etapa 1 de\r\nConocimientos2030. Este, a su vez, est\u00e1 basado en un diagn\u00f3stico exhaustivo que incluy\u00f3\r\nan\u00e1lisis interno, territorial (de cada provincia del Valle Central) y benchmarking con\r\ninstituciones de referencia. Como resultado, se identificaron una serie de dificultades en\r\nnuestras unidades que son relevantes para la transformaci\u00f3n de los procesos acad\u00e9micos.\r\nEntre ellas:\r\n\u0095 Rigidez de los programas formativos y uso de metodolog\u00edas encasilladas en las\r\ndisciplinas, que dificultan el an\u00e1lisis de la realidad social y p\u00fablica.\r\n\u0095 Limitada incorporaci\u00f3n de las complejidades del territorio a la formaci\u00f3n, afectando\r\nnegativamente a la relaci\u00f3n bidireccional y al desarrollo de iniciativas innovadoras.\r\n\u0095 Iniciativas acad\u00e9micas se acotan a fondos p\u00fablicos y muy competitivos, siendo\r\nexcepciones aquellos del sector privado o de inter\u00e9s p\u00fablico.\r\n\u0095 Desarrollo incipiente de la inter y transdisciplina (en adelante, ITD), e insuficiente\r\ntransferencia de conocimientos y tecnolog\u00edas.\r\n\u0095 Procesos de desarrollo acad\u00e9mico enfatizan el crecimiento individual, poco claros\r\npara acad\u00e9micos.as del \u00e1rea de las artes o con enfoque en ITD. Existen diferencias\r\nde g\u00e9nero favorables a hombres en jerarquizaci\u00f3n, publicaciones y proyectos\r\nobtenidos.\r\n\u0095 Gesti\u00f3n acad\u00e9mica desarticulada entre las unidades, observ\u00e1ndose repetici\u00f3n de\r\nprocesos de gesti\u00f3n entre las unidades participantes.\r\n\u0095 Los miembros de la comunidad indican percibir lo que denominan \u0093extractivismo\r\nacad\u00e9mico\u0094, una pr\u00e1ctica acad\u00e9mica en donde el v\u00ednculo con las comunidades\r\ntermina con la recogida de datos. Adem\u00e1s, el conocimiento universitario no es de\r\nf\u00e1cil acceso.\r\nEl an\u00e1lisis y discusi\u00f3n de las consecuencias de dichas limitaciones derivaron en el\r\nplanteamiento de propuestas, que buscan generar transformaci\u00f3n en nuestros procesos\r\nacad\u00e9micos, fomentando la flexibilidad curricular, la ITD, la generaci\u00f3n de conocimientos con atenci\u00f3n al territorio y la promoci\u00f3n de la equidad entre personas y la participaci\u00f3n\r\nfemenina en roles de liderazgo. Algunas de ellas son:\r\n1. Conformar un consorcio interuniversitario en HACS de las Universidades P\u00fablicas de\r\nlas Regiones VI y VII, cuya gobernanza colaborativa promueva transformaciones en\r\nlos procesos formativos, de investigaci\u00f3n y creaci\u00f3n, vinculaci\u00f3n con el medio (VcM)\r\ny gesti\u00f3n en ambas universidades. Posee sellos espec\u00edficos en fomento del\r\npatrimonio, de salud mental y bienestar, equidad de g\u00e9nero y derechos humanos y\r\npromueve la discusi\u00f3n y desarrollo de pol\u00edticas p\u00fablicas regionales y nacionales.\r\n2. Redise\u00f1ar carreras de pregrado HACS en cada universidad, flexibles, incorporando\r\nmetodolog\u00edas ITD y problem\u00e1ticas del Valle Central, formando as\u00ed competencias de\r\ntransferencia de conocimientos para la innovaci\u00f3n social y la pol\u00edtica p\u00fablica y\r\ncultural.\r\n3. Formular e implementar programas de estudio interuniversitarios, con un modelo\r\nequivalente a los pregrados redise\u00f1ados, con foco en formaci\u00f3n continua y\r\npostgrado.\r\n4. Construir micro-certificaciones al alero de los planes de estudio de pregrado,\r\npromoviendo la flexibilidad curricular y la innovaci\u00f3n para las profesiones del futuro.\r\n5. Crear una comisi\u00f3n paritaria de g\u00e9nero, ocupada de generaci\u00f3n consorciada de\r\npropuestas y seguimiento de datos para el logro de la equidad de g\u00e9nero, abierto a\r\nla comunidad universitaria y del Valle Central.\r\n6. Constituir equipos de investigaci\u00f3n\/creaci\u00f3n con foco ITD e interuniversitario,\r\nincorporando problem\u00e1ticas del Valle Central y promoviendo la discusi\u00f3n y\r\ngeneraci\u00f3n de pol\u00edticas p\u00fablicas en las \u00e1reas de desarrollo.\r\n7. Habilitar un espacio f\u00edsico independiente a las facultades, donde las personas que se\r\nadscriben desarrollen ITD de manera abierta y colaborativa con otros acad\u00e9micos,\r\nestudiantes y\/o miembros de la sociedad civil.\r\n8. Creaci\u00f3n de una gobernanza que involucre a la comunidad acad\u00e9mica, estudiantil y\r\nde la comuna, para la ejecuci\u00f3n y asesor\u00eda de las acciones programadas, enfatizando\r\nlos sellos del proyecto y acercando las propuestas al desarrollo y logro de pol\u00edticas\r\np\u00fablicas.\r\n9. Presentar a las autoridades superiores universitarias un perfil de desarrollo de\r\nacad\u00e9micas.os HACS con \u00e9nfasis en indicadores para la jerarquizaci\u00f3n,\r\nhomologando con ello las trayectorias acad\u00e9micas en todas las disciplinas\r\nuniversitarias (especialmente artes) incorporando enfoque ITD.\r\n10.Promover la democratizaci\u00f3n del conocimiento a partir del uso de herramientas de\r\nciencia abierta, incorpor\u00e1ndolas en el desarrollo de la formaci\u00f3n, y a trav\u00e9s del uso\r\nde repositorios para el almacenamiento de informaci\u00f3n de todas las disciplinas\r\nHACS.\r\nConsideramos que los conocimientos de nuestros territorios son una oportunidad para el\r\nmejoramiento de nuestros planes de formaci\u00f3n, as\u00ed como para proponer otros nuevos que\r\narticulen las capacidades de los planteles universitarios. Esta propuesta plantea que es\r\nprioritaria la capacitaci\u00f3n docente en estrategias ITD, permitiendo con ello el abordaje de problemas relevantes para el territorio desde una perspectiva amplia. Todo lo anterior,\r\npermitir\u00e1 formar profesionales capacitados para desarrollarse en entornos complejos.\r\nEn el campo de la investigaci\u00f3n la propuesta considera la creaci\u00f3n de grupos de trabajo\r\nITD en tem\u00e1ticas espec\u00edficas de desarrollo para las HACS, enfatizando los temas de\r\nPatrimonio, Salud Mental y Bienestar, y Liderazgo de Mujeres. Estos grupos deber\u00e1n\r\npromover el liderazgo de mujeres en sus propuestas, relacionarse con su espacio de inter\u00e9s\r\ne involucrar a los actores sociales de manera activa y rec\u00edproca. El objetivo es crear, en 10\r\na\u00f1os, grupos de referencia nacional en investigaci\u00f3n b\u00e1sica, aplicada y art\u00edstica con base\r\nen ITD permitiendo, as\u00ed, sustentabilidad de las estrategias de desarrollo m\u00e1s all\u00e1 del\r\nperiodo de financiaci\u00f3n. Construir un camino de desarrollo acad\u00e9mico para las HACS,\r\nbasado en ITD y con especial atenci\u00f3n a las artes permitir\u00e1 mayor equidad disciplinar en\r\neste proceso y orientaci\u00f3n para el desarrollo, aumentando as\u00ed el valor de los conocimientos\r\ncient\u00edficos, creativos y tradicionales para la instituci\u00f3n.\r\nPretendemos construir una estrategia de VcM sustentada en conocimiento cient\u00edfico y\r\ncreativo, promoviendo con ello la innovaci\u00f3n, la transferencia y el escalamiento de\r\nproductos, en donde participa de manera activa la comunidad no acad\u00e9mica de nuestros\r\nterritorios. Es nuestro inter\u00e9s democratizar el conocimiento y abrirlo a nuestras\r\ncomunidades a trav\u00e9s de mecanismos de ciencia abierta y, por \u00faltimo, una gobernanza\r\neficiente para articular nuestros objetivos y metas, desarrollando herramientas de\r\ndiscusi\u00f3n colaborativa, seguimiento y evaluaci\u00f3n de impacto para la mejora continua.\r\nEl horizonte de desarrollo de nuestras iniciativas es de diez a\u00f1os, comprometiendo al sexto\r\na\u00f1o de ejecuci\u00f3n una serie de acciones que involucran, en ambas regiones, un\r\nacercamiento de cada instituci\u00f3n a su espacio de influencia y colaboraci\u00f3n entre ellas. As\u00ed\r\nmismo, esperamos constituir un espacio consorciado que promueve una formaci\u00f3n\r\nprofesional sensible a las necesidades del entorno y cuyos estudiantes poseen\r\ncompetencias para atenderlas en colaboraci\u00f3n con sus habitantes; que capacita a\r\nacad\u00e9micos y profesionales en mecanismos de promoci\u00f3n de la ITD; que participa en la\r\ndiscusi\u00f3n y generaci\u00f3n de pol\u00edticas p\u00fablicas; que desarrolla conocimiento ITD a trav\u00e9s de\r\ngrupos cuya investigaci\u00f3n se aplica a temas espec\u00edficos, siendo referentes a nivel nacional;\r\nque se relaciona con el entorno de manera cooperativa y bidireccional, cuyos conocimientos\r\nson la base de la innovaci\u00f3n y la transferencia. Y, por \u00faltimo, un espacio que promueve la\r\nequidad de g\u00e9nero, la participaci\u00f3n de mujeres en espacios de liderazgo y la participaci\u00f3n\r\nsocial de nuestros territorios.\r\nFinalmente, podremos configurarnos como un consorcio universitario con gran presencia\r\nen sus regiones y que desarrolle un trabajo virtuoso con diferentes actores del mundo\r\nuniversitario y de la sociedad civil, quienes asesorar\u00e1n nuestro trabajo de manera que\r\natiendan a pol\u00edticas p\u00fablicas y necesidades de los territorios.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26505\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Cambio clim\u00e1tico y econom\u00eda: an\u00e1lisis de riesgos y soluciones para sectores estrat\u00e9gicos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26505\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26505\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto \u0093Cambio clim\u00e1tico y econom\u00eda: an\u00e1lisis de riesgos y soluciones para sectores estrat\u00e9gicos\u0094 busca fortalecer las capacidades regionales de la Macrozona para enfrentar los crecientes desaf\u00edos del cambio clim\u00e1tico mediante la creaci\u00f3n de una red internacional de cooperaci\u00f3n cient\u00edfica. \r\nLa iniciativa se estructura en torno a tres ejes: la identificaci\u00f3n y cuantificaci\u00f3n de riesgos clim\u00e1ticos a nivel subregional, utilizando herramientas como im\u00e1genes satelitales, modelos de teor\u00eda de juegos y simulaciones; el an\u00e1lisis de c\u00f3mo hogares, productores y gobiernos ajustan sus decisiones ; y el fortalecimiento de capacidades mediante pasant\u00edas internacionales, talleres, formaci\u00f3n de estudiantes y la publicaci\u00f3n de resultados.\r\nUn componente central del proyecto es el intercambio de experiencias entre pa\u00edses en desarrollo, M\u00e9xico, Brasil y Chile, que comparten desaf\u00edos estructurales como alta informalidad laboral, barreras en el acceso al cr\u00e9dito y vulnerabilidad territorial frente al cambio clim\u00e1tico. Adem\u00e1s, el proyecto pone un fuerte \u00e9nfasis en la formaci\u00f3n de capital humano, incorporando a tesistas de pregrado y posgrado en todas las etapas de investigaci\u00f3n. Ellas\/os participar\u00e1n en actividades clave como dise\u00f1o de modelos, recolecci\u00f3n y an\u00e1lisis de datos, y redacci\u00f3n de informes, fortaleciendo sus competencias t\u00e9cnicas y su vinculaci\u00f3n con redes internacionales. Se ofrecer\u00e1n tambi\u00e9n un workshop y un taller, orientado a fortalecer las capacidades en temas de econom\u00eda del cambio clim\u00e1tico.\r\nParticipan la Universidad de O\u0092Higgins y la Universidad de los Andes de Chile; y como socios internacionales el Banco Central de M\u00e9xico y la Fundaci\u00f3n Getulio Vargas de Brasil. Esta colaboraci\u00f3n busca generar evidencia territorialmente situada para el dise\u00f1o de planes de resiliencia agr\u00edcola, descentralizar la formaci\u00f3n cient\u00edfica en Chile y consolidar una red duradera de investigaci\u00f3n aplicada en econom\u00eda del cambio clim\u00e1tico con impacto regional y latinoamericano.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26506\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Conocimientos 2030 Etapa 2\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26506\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26506\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las regiones de O\u0092Higgins y el Maule tienen una historia com\u00fan, caracter\u00edsticas y un\r\ndesarrollo social similar. Ambas regiones, ubicadas en el Valle Central chileno, comparten\r\nelementos culturales, s\u00edmbolos, historias y personajes que, su conjunto, reflejan la\r\nidentidad chilena. La historia de estos territorios incluye conocimiento diverso sobre\r\nnuestro pasado reciente y lejano en forma de relatos, pinturas, medios de transporte,\r\nmecanismos de comercializaci\u00f3n, oficios y manifestaciones culturales, que son comunes a\r\nellas. Debido a las importantes similitudes territoriales, humanas y productivas que poseen\r\nlas regiones de O\u0092Higgins y el Maule, es que sus universidades estatales proponen la\r\ninstitucionalizaci\u00f3n de un consorcio interuniversitario para fortalecer las Humanidades,\r\nArtes y Ciencias Sociales (HACS) en el Valle Central de Chile, transformando procesos\r\nacad\u00e9micos y generando instancias de participaci\u00f3n activa con la comunidad territorial.\r\nEste consorcio interuniversitario entre la Universidad de Talca y la Universidad de O\u0092Higgins\r\nse denomina \u0093Consorcio del Valle Central\u0094, en su af\u00e1n por ver representadas las realidades\r\ny conocimientos territoriales de la costa, del centro y de la cordillera de la VII y VI Regi\u00f3n.\r\nLa creaci\u00f3n del Consorcio Valle Central est\u00e1 sustentada en el Plan Estrat\u00e9gico para el\r\nFortalecimiento de las HACS, construido como producto de la etapa 1 de\r\nConocimientos2030. Este, a su vez, est\u00e1 basado en un diagn\u00f3stico exhaustivo que incluy\u00f3\r\nan\u00e1lisis interno, territorial (de cada provincia del Valle Central) y benchmarking con\r\ninstituciones de referencia. Como resultado, se identificaron una serie de dificultades en\r\nnuestras unidades que son relevantes para la transformaci\u00f3n de los procesos acad\u00e9micos.\r\nEntre ellas:\r\n\u0095 Rigidez de los programas formativos y uso de metodolog\u00edas encasilladas en las\r\ndisciplinas, que dificultan el an\u00e1lisis de la realidad social y p\u00fablica.\r\n\u0095 Limitada incorporaci\u00f3n de las complejidades del territorio a la formaci\u00f3n, afectando\r\nnegativamente a la relaci\u00f3n bidireccional y al desarrollo de iniciativas innovadoras.\r\n\u0095 Iniciativas acad\u00e9micas se acotan a fondos p\u00fablicos y muy competitivos, siendo\r\nexcepciones aquellos del sector privado o de inter\u00e9s p\u00fablico.\r\n\u0095 Desarrollo incipiente de la inter y transdisciplina (en adelante, ITD), e insuficiente\r\ntransferencia de conocimientos y tecnolog\u00edas.\r\n\u0095 Procesos de desarrollo acad\u00e9mico enfatizan el crecimiento individual, poco claros\r\npara acad\u00e9micos.as del \u00e1rea de las artes o con enfoque en ITD. Existen diferencias\r\nde g\u00e9nero favorables a hombres en jerarquizaci\u00f3n, publicaciones y proyectos\r\nobtenidos.\r\n\u0095 Gesti\u00f3n acad\u00e9mica desarticulada entre las unidades, observ\u00e1ndose repetici\u00f3n de\r\nprocesos de gesti\u00f3n entre las unidades participantes.\r\n\u0095 Los miembros de la comunidad indican percibir lo que denominan \u0093extractivismo\r\nacad\u00e9mico\u0094, una pr\u00e1ctica acad\u00e9mica en donde el v\u00ednculo con las comunidades\r\ntermina con la recogida de datos. Adem\u00e1s, el conocimiento universitario no es de\r\nf\u00e1cil acceso.\r\nEl an\u00e1lisis y discusi\u00f3n de las consecuencias de dichas limitaciones derivaron en el\r\nplanteamiento de propuestas, que buscan generar transformaci\u00f3n en nuestros procesos\r\nacad\u00e9micos, fomentando la flexibilidad curricular, la ITD, la generaci\u00f3n de conocimientos con atenci\u00f3n al territorio y la promoci\u00f3n de la equidad entre personas y la participaci\u00f3n\r\nfemenina en roles de liderazgo. Algunas de ellas son:\r\n1. Conformar un consorcio interuniversitario en HACS de las Universidades P\u00fablicas de\r\nlas Regiones VI y VII, cuya gobernanza colaborativa promueva transformaciones en\r\nlos procesos formativos, de investigaci\u00f3n y creaci\u00f3n, vinculaci\u00f3n con el medio (VcM)\r\ny gesti\u00f3n en ambas universidades. Posee sellos espec\u00edficos en fomento del\r\npatrimonio, de salud mental y bienestar, equidad de g\u00e9nero y derechos humanos y\r\npromueve la discusi\u00f3n y desarrollo de pol\u00edticas p\u00fablicas regionales y nacionales.\r\n2. Redise\u00f1ar carreras de pregrado HACS en cada universidad, flexibles, incorporando\r\nmetodolog\u00edas ITD y problem\u00e1ticas del Valle Central, formando as\u00ed competencias de\r\ntransferencia de conocimientos para la innovaci\u00f3n social y la pol\u00edtica p\u00fablica y\r\ncultural.\r\n3. Formular e implementar programas de estudio interuniversitarios, con un modelo\r\nequivalente a los pregrados redise\u00f1ados, con foco en formaci\u00f3n continua y\r\npostgrado.\r\n4. Construir micro-certificaciones al alero de los planes de estudio de pregrado,\r\npromoviendo la flexibilidad curricular y la innovaci\u00f3n para las profesiones del futuro.\r\n5. Crear una comisi\u00f3n paritaria de g\u00e9nero, ocupada de generaci\u00f3n consorciada de\r\npropuestas y seguimiento de datos para el logro de la equidad de g\u00e9nero, abierto a\r\nla comunidad universitaria y del Valle Central.\r\n6. Constituir equipos de investigaci\u00f3n\/creaci\u00f3n con foco ITD e interuniversitario,\r\nincorporando problem\u00e1ticas del Valle Central y promoviendo la discusi\u00f3n y\r\ngeneraci\u00f3n de pol\u00edticas p\u00fablicas en las \u00e1reas de desarrollo.\r\n7. Habilitar un espacio f\u00edsico independiente a las facultades, donde las personas que se\r\nadscriben desarrollen ITD de manera abierta y colaborativa con otros acad\u00e9micos,\r\nestudiantes y\/o miembros de la sociedad civil.\r\n8. Creaci\u00f3n de una gobernanza que involucre a la comunidad acad\u00e9mica, estudiantil y\r\nde la comuna, para la ejecuci\u00f3n y asesor\u00eda de las acciones programadas, enfatizando\r\nlos sellos del proyecto y acercando las propuestas al desarrollo y logro de pol\u00edticas\r\np\u00fablicas.\r\n9. Presentar a las autoridades superiores universitarias un perfil de desarrollo de\r\nacad\u00e9micas.os HACS con \u00e9nfasis en indicadores para la jerarquizaci\u00f3n,\r\nhomologando con ello las trayectorias acad\u00e9micas en todas las disciplinas\r\nuniversitarias (especialmente artes) incorporando enfoque ITD.\r\n10.Promover la democratizaci\u00f3n del conocimiento a partir del uso de herramientas de\r\nciencia abierta, incorpor\u00e1ndolas en el desarrollo de la formaci\u00f3n, y a trav\u00e9s del uso\r\nde repositorios para el almacenamiento de informaci\u00f3n de todas las disciplinas\r\nHACS.\r\nConsideramos que los conocimientos de nuestros territorios son una oportunidad para el\r\nmejoramiento de nuestros planes de formaci\u00f3n, as\u00ed como para proponer otros nuevos que\r\narticulen las capacidades de los planteles universitarios. Esta propuesta plantea que es\r\nprioritaria la capacitaci\u00f3n docente en estrategias ITD, permitiendo con ello el abordaje de problemas relevantes para el territorio desde una perspectiva amplia. Todo lo anterior,\r\npermitir\u00e1 formar profesionales capacitados para desarrollarse en entornos complejos.\r\nEn el campo de la investigaci\u00f3n la propuesta considera la creaci\u00f3n de grupos de trabajo\r\nITD en tem\u00e1ticas espec\u00edficas de desarrollo para las HACS, enfatizando los temas de\r\nPatrimonio, Salud Mental y Bienestar, y Liderazgo de Mujeres. Estos grupos deber\u00e1n\r\npromover el liderazgo de mujeres en sus propuestas, relacionarse con su espacio de inter\u00e9s\r\ne involucrar a los actores sociales de manera activa y rec\u00edproca. El objetivo es crear, en 10\r\na\u00f1os, grupos de referencia nacional en investigaci\u00f3n b\u00e1sica, aplicada y art\u00edstica con base\r\nen ITD permitiendo, as\u00ed, sustentabilidad de las estrategias de desarrollo m\u00e1s all\u00e1 del\r\nperiodo de financiaci\u00f3n. Construir un camino de desarrollo acad\u00e9mico para las HACS,\r\nbasado en ITD y con especial atenci\u00f3n a las artes permitir\u00e1 mayor equidad disciplinar en\r\neste proceso y orientaci\u00f3n para el desarrollo, aumentando as\u00ed el valor de los conocimientos\r\ncient\u00edficos, creativos y tradicionales para la instituci\u00f3n.\r\nPretendemos construir una estrategia de VcM sustentada en conocimiento cient\u00edfico y\r\ncreativo, promoviendo con ello la innovaci\u00f3n, la transferencia y el escalamiento de\r\nproductos, en donde participa de manera activa la comunidad no acad\u00e9mica de nuestros\r\nterritorios. Es nuestro inter\u00e9s democratizar el conocimiento y abrirlo a nuestras\r\ncomunidades a trav\u00e9s de mecanismos de ciencia abierta y, por \u00faltimo, una gobernanza\r\neficiente para articular nuestros objetivos y metas, desarrollando herramientas de\r\ndiscusi\u00f3n colaborativa, seguimiento y evaluaci\u00f3n de impacto para la mejora continua.\r\nEl horizonte de desarrollo de nuestras iniciativas es de diez a\u00f1os, comprometiendo al sexto\r\na\u00f1o de ejecuci\u00f3n una serie de acciones que involucran, en ambas regiones, un\r\nacercamiento de cada instituci\u00f3n a su espacio de influencia y colaboraci\u00f3n entre ellas. As\u00ed\r\nmismo, esperamos constituir un espacio consorciado que promueve una formaci\u00f3n\r\nprofesional sensible a las necesidades del entorno y cuyos estudiantes poseen\r\ncompetencias para atenderlas en colaboraci\u00f3n con sus habitantes; que capacita a\r\nacad\u00e9micos y profesionales en mecanismos de promoci\u00f3n de la ITD; que participa en la\r\ndiscusi\u00f3n y generaci\u00f3n de pol\u00edticas p\u00fablicas; que desarrolla conocimiento ITD a trav\u00e9s de\r\ngrupos cuya investigaci\u00f3n se aplica a temas espec\u00edficos, siendo referentes a nivel nacional;\r\nque se relaciona con el entorno de manera cooperativa y bidireccional, cuyos conocimientos\r\nson la base de la innovaci\u00f3n y la transferencia. Y, por \u00faltimo, un espacio que promueve la\r\nequidad de g\u00e9nero, la participaci\u00f3n de mujeres en espacios de liderazgo y la participaci\u00f3n\r\nsocial de nuestros territorios.\r\nFinalmente, podremos configurarnos como un consorcio universitario con gran presencia\r\nen sus regiones y que desarrolle un trabajo virtuoso con diferentes actores del mundo\r\nuniversitario y de la sociedad civil, quienes asesorar\u00e1n nuestro trabajo de manera que\r\natiendan a pol\u00edticas p\u00fablicas y necesidades de los territorios.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26515\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Conocimientos 2030 Etapa 2\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26515\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26515\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las regiones de O\u0092Higgins y el Maule tienen una historia com\u00fan, caracter\u00edsticas y un\r\ndesarrollo social similar. Ambas regiones, ubicadas en el Valle Central chileno, comparten\r\nelementos culturales, s\u00edmbolos, historias y personajes que, su conjunto, reflejan la\r\nidentidad chilena. La historia de estos territorios incluye conocimiento diverso sobre\r\nnuestro pasado reciente y lejano en forma de relatos, pinturas, medios de transporte,\r\nmecanismos de comercializaci\u00f3n, oficios y manifestaciones culturales, que son comunes a\r\nellas. Debido a las importantes similitudes territoriales, humanas y productivas que poseen\r\nlas regiones de O\u0092Higgins y el Maule, es que sus universidades estatales proponen la\r\ninstitucionalizaci\u00f3n de un consorcio interuniversitario para fortalecer las Humanidades,\r\nArtes y Ciencias Sociales (HACS) en el Valle Central de Chile, transformando procesos\r\nacad\u00e9micos y generando instancias de participaci\u00f3n activa con la comunidad territorial.\r\nEste consorcio interuniversitario entre la Universidad de Talca y la Universidad de O\u0092Higgins\r\nse denomina \u0093Consorcio del Valle Central\u0094, en su af\u00e1n por ver representadas las realidades\r\ny conocimientos territoriales de la costa, del centro y de la cordillera de la VII y VI Regi\u00f3n.\r\nLa creaci\u00f3n del Consorcio Valle Central est\u00e1 sustentada en el Plan Estrat\u00e9gico para el\r\nFortalecimiento de las HACS, construido como producto de la etapa 1 de\r\nConocimientos2030. Este, a su vez, est\u00e1 basado en un diagn\u00f3stico exhaustivo que incluy\u00f3\r\nan\u00e1lisis interno, territorial (de cada provincia del Valle Central) y benchmarking con\r\ninstituciones de referencia. Como resultado, se identificaron una serie de dificultades en\r\nnuestras unidades que son relevantes para la transformaci\u00f3n de los procesos acad\u00e9micos.\r\nEntre ellas:\r\n\u0095 Rigidez de los programas formativos y uso de metodolog\u00edas encasilladas en las\r\ndisciplinas, que dificultan el an\u00e1lisis de la realidad social y p\u00fablica.\r\n\u0095 Limitada incorporaci\u00f3n de las complejidades del territorio a la formaci\u00f3n, afectando\r\nnegativamente a la relaci\u00f3n bidireccional y al desarrollo de iniciativas innovadoras.\r\n\u0095 Iniciativas acad\u00e9micas se acotan a fondos p\u00fablicos y muy competitivos, siendo\r\nexcepciones aquellos del sector privado o de inter\u00e9s p\u00fablico.\r\n\u0095 Desarrollo incipiente de la inter y transdisciplina (en adelante, ITD), e insuficiente\r\ntransferencia de conocimientos y tecnolog\u00edas.\r\n\u0095 Procesos de desarrollo acad\u00e9mico enfatizan el crecimiento individual, poco claros\r\npara acad\u00e9micos.as del \u00e1rea de las artes o con enfoque en ITD. Existen diferencias\r\nde g\u00e9nero favorables a hombres en jerarquizaci\u00f3n, publicaciones y proyectos\r\nobtenidos.\r\n\u0095 Gesti\u00f3n acad\u00e9mica desarticulada entre las unidades, observ\u00e1ndose repetici\u00f3n de\r\nprocesos de gesti\u00f3n entre las unidades participantes.\r\n\u0095 Los miembros de la comunidad indican percibir lo que denominan \u0093extractivismo\r\nacad\u00e9mico\u0094, una pr\u00e1ctica acad\u00e9mica en donde el v\u00ednculo con las comunidades\r\ntermina con la recogida de datos. Adem\u00e1s, el conocimiento universitario no es de\r\nf\u00e1cil acceso.\r\nEl an\u00e1lisis y discusi\u00f3n de las consecuencias de dichas limitaciones derivaron en el\r\nplanteamiento de propuestas, que buscan generar transformaci\u00f3n en nuestros procesos\r\nacad\u00e9micos, fomentando la flexibilidad curricular, la ITD, la generaci\u00f3n de conocimientos con atenci\u00f3n al territorio y la promoci\u00f3n de la equidad entre personas y la participaci\u00f3n\r\nfemenina en roles de liderazgo. Algunas de ellas son:\r\n1. Conformar un consorcio interuniversitario en HACS de las Universidades P\u00fablicas de\r\nlas Regiones VI y VII, cuya gobernanza colaborativa promueva transformaciones en\r\nlos procesos formativos, de investigaci\u00f3n y creaci\u00f3n, vinculaci\u00f3n con el medio (VcM)\r\ny gesti\u00f3n en ambas universidades. Posee sellos espec\u00edficos en fomento del\r\npatrimonio, de salud mental y bienestar, equidad de g\u00e9nero y derechos humanos y\r\npromueve la discusi\u00f3n y desarrollo de pol\u00edticas p\u00fablicas regionales y nacionales.\r\n2. Redise\u00f1ar carreras de pregrado HACS en cada universidad, flexibles, incorporando\r\nmetodolog\u00edas ITD y problem\u00e1ticas del Valle Central, formando as\u00ed competencias de\r\ntransferencia de conocimientos para la innovaci\u00f3n social y la pol\u00edtica p\u00fablica y\r\ncultural.\r\n3. Formular e implementar programas de estudio interuniversitarios, con un modelo\r\nequivalente a los pregrados redise\u00f1ados, con foco en formaci\u00f3n continua y\r\npostgrado.\r\n4. Construir micro-certificaciones al alero de los planes de estudio de pregrado,\r\npromoviendo la flexibilidad curricular y la innovaci\u00f3n para las profesiones del futuro.\r\n5. Crear una comisi\u00f3n paritaria de g\u00e9nero, ocupada de generaci\u00f3n consorciada de\r\npropuestas y seguimiento de datos para el logro de la equidad de g\u00e9nero, abierto a\r\nla comunidad universitaria y del Valle Central.\r\n6. Constituir equipos de investigaci\u00f3n\/creaci\u00f3n con foco ITD e interuniversitario,\r\nincorporando problem\u00e1ticas del Valle Central y promoviendo la discusi\u00f3n y\r\ngeneraci\u00f3n de pol\u00edticas p\u00fablicas en las \u00e1reas de desarrollo.\r\n7. Habilitar un espacio f\u00edsico independiente a las facultades, donde las personas que se\r\nadscriben desarrollen ITD de manera abierta y colaborativa con otros acad\u00e9micos,\r\nestudiantes y\/o miembros de la sociedad civil.\r\n8. Creaci\u00f3n de una gobernanza que involucre a la comunidad acad\u00e9mica, estudiantil y\r\nde la comuna, para la ejecuci\u00f3n y asesor\u00eda de las acciones programadas, enfatizando\r\nlos sellos del proyecto y acercando las propuestas al desarrollo y logro de pol\u00edticas\r\np\u00fablicas.\r\n9. Presentar a las autoridades superiores universitarias un perfil de desarrollo de\r\nacad\u00e9micas.os HACS con \u00e9nfasis en indicadores para la jerarquizaci\u00f3n,\r\nhomologando con ello las trayectorias acad\u00e9micas en todas las disciplinas\r\nuniversitarias (especialmente artes) incorporando enfoque ITD.\r\n10.Promover la democratizaci\u00f3n del conocimiento a partir del uso de herramientas de\r\nciencia abierta, incorpor\u00e1ndolas en el desarrollo de la formaci\u00f3n, y a trav\u00e9s del uso\r\nde repositorios para el almacenamiento de informaci\u00f3n de todas las disciplinas\r\nHACS.\r\nConsideramos que los conocimientos de nuestros territorios son una oportunidad para el\r\nmejoramiento de nuestros planes de formaci\u00f3n, as\u00ed como para proponer otros nuevos que\r\narticulen las capacidades de los planteles universitarios. Esta propuesta plantea que es\r\nprioritaria la capacitaci\u00f3n docente en estrategias ITD, permitiendo con ello el abordaje de problemas relevantes para el territorio desde una perspectiva amplia. Todo lo anterior,\r\npermitir\u00e1 formar profesionales capacitados para desarrollarse en entornos complejos.\r\nEn el campo de la investigaci\u00f3n la propuesta considera la creaci\u00f3n de grupos de trabajo\r\nITD en tem\u00e1ticas espec\u00edficas de desarrollo para las HACS, enfatizando los temas de\r\nPatrimonio, Salud Mental y Bienestar, y Liderazgo de Mujeres. Estos grupos deber\u00e1n\r\npromover el liderazgo de mujeres en sus propuestas, relacionarse con su espacio de inter\u00e9s\r\ne involucrar a los actores sociales de manera activa y rec\u00edproca. El objetivo es crear, en 10\r\na\u00f1os, grupos de referencia nacional en investigaci\u00f3n b\u00e1sica, aplicada y art\u00edstica con base\r\nen ITD permitiendo, as\u00ed, sustentabilidad de las estrategias de desarrollo m\u00e1s all\u00e1 del\r\nperiodo de financiaci\u00f3n. Construir un camino de desarrollo acad\u00e9mico para las HACS,\r\nbasado en ITD y con especial atenci\u00f3n a las artes permitir\u00e1 mayor equidad disciplinar en\r\neste proceso y orientaci\u00f3n para el desarrollo, aumentando as\u00ed el valor de los conocimientos\r\ncient\u00edficos, creativos y tradicionales para la instituci\u00f3n.\r\nPretendemos construir una estrategia de VcM sustentada en conocimiento cient\u00edfico y\r\ncreativo, promoviendo con ello la innovaci\u00f3n, la transferencia y el escalamiento de\r\nproductos, en donde participa de manera activa la comunidad no acad\u00e9mica de nuestros\r\nterritorios. Es nuestro inter\u00e9s democratizar el conocimiento y abrirlo a nuestras\r\ncomunidades a trav\u00e9s de mecanismos de ciencia abierta y, por \u00faltimo, una gobernanza\r\neficiente para articular nuestros objetivos y metas, desarrollando herramientas de\r\ndiscusi\u00f3n colaborativa, seguimiento y evaluaci\u00f3n de impacto para la mejora continua.\r\nEl horizonte de desarrollo de nuestras iniciativas es de diez a\u00f1os, comprometiendo al sexto\r\na\u00f1o de ejecuci\u00f3n una serie de acciones que involucran, en ambas regiones, un\r\nacercamiento de cada instituci\u00f3n a su espacio de influencia y colaboraci\u00f3n entre ellas. As\u00ed\r\nmismo, esperamos constituir un espacio consorciado que promueve una formaci\u00f3n\r\nprofesional sensible a las necesidades del entorno y cuyos estudiantes poseen\r\ncompetencias para atenderlas en colaboraci\u00f3n con sus habitantes; que capacita a\r\nacad\u00e9micos y profesionales en mecanismos de promoci\u00f3n de la ITD; que participa en la\r\ndiscusi\u00f3n y generaci\u00f3n de pol\u00edticas p\u00fablicas; que desarrolla conocimiento ITD a trav\u00e9s de\r\ngrupos cuya investigaci\u00f3n se aplica a temas espec\u00edficos, siendo referentes a nivel nacional;\r\nque se relaciona con el entorno de manera cooperativa y bidireccional, cuyos conocimientos\r\nson la base de la innovaci\u00f3n y la transferencia. Y, por \u00faltimo, un espacio que promueve la\r\nequidad de g\u00e9nero, la participaci\u00f3n de mujeres en espacios de liderazgo y la participaci\u00f3n\r\nsocial de nuestros territorios.\r\nFinalmente, podremos configurarnos como un consorcio universitario con gran presencia\r\nen sus regiones y que desarrolle un trabajo virtuoso con diferentes actores del mundo\r\nuniversitario y de la sociedad civil, quienes asesorar\u00e1n nuestro trabajo de manera que\r\natiendan a pol\u00edticas p\u00fablicas y necesidades de los territorios.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26545\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Conocimientos 2030 Etapa 2\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26545\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26545\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las regiones de O\u0092Higgins y el Maule tienen una historia com\u00fan, caracter\u00edsticas y un\r\ndesarrollo social similar. Ambas regiones, ubicadas en el Valle Central chileno, comparten\r\nelementos culturales, s\u00edmbolos, historias y personajes que, su conjunto, reflejan la\r\nidentidad chilena. La historia de estos territorios incluye conocimiento diverso sobre\r\nnuestro pasado reciente y lejano en forma de relatos, pinturas, medios de transporte,\r\nmecanismos de comercializaci\u00f3n, oficios y manifestaciones culturales, que son comunes a\r\nellas. Debido a las importantes similitudes territoriales, humanas y productivas que poseen\r\nlas regiones de O\u0092Higgins y el Maule, es que sus universidades estatales proponen la\r\ninstitucionalizaci\u00f3n de un consorcio interuniversitario para fortalecer las Humanidades,\r\nArtes y Ciencias Sociales (HACS) en el Valle Central de Chile, transformando procesos\r\nacad\u00e9micos y generando instancias de participaci\u00f3n activa con la comunidad territorial.\r\nEste consorcio interuniversitario entre la Universidad de Talca y la Universidad de O\u0092Higgins\r\nse denomina \u0093Consorcio del Valle Central\u0094, en su af\u00e1n por ver representadas las realidades\r\ny conocimientos territoriales de la costa, del centro y de la cordillera de la VII y VI Regi\u00f3n.\r\nLa creaci\u00f3n del Consorcio Valle Central est\u00e1 sustentada en el Plan Estrat\u00e9gico para el\r\nFortalecimiento de las HACS, construido como producto de la etapa 1 de\r\nConocimientos2030. Este, a su vez, est\u00e1 basado en un diagn\u00f3stico exhaustivo que incluy\u00f3\r\nan\u00e1lisis interno, territorial (de cada provincia del Valle Central) y benchmarking con\r\ninstituciones de referencia. Como resultado, se identificaron una serie de dificultades en\r\nnuestras unidades que son relevantes para la transformaci\u00f3n de los procesos acad\u00e9micos.\r\nEntre ellas:\r\n\u0095 Rigidez de los programas formativos y uso de metodolog\u00edas encasilladas en las\r\ndisciplinas, que dificultan el an\u00e1lisis de la realidad social y p\u00fablica.\r\n\u0095 Limitada incorporaci\u00f3n de las complejidades del territorio a la formaci\u00f3n, afectando\r\nnegativamente a la relaci\u00f3n bidireccional y al desarrollo de iniciativas innovadoras.\r\n\u0095 Iniciativas acad\u00e9micas se acotan a fondos p\u00fablicos y muy competitivos, siendo\r\nexcepciones aquellos del sector privado o de inter\u00e9s p\u00fablico.\r\n\u0095 Desarrollo incipiente de la inter y transdisciplina (en adelante, ITD), e insuficiente\r\ntransferencia de conocimientos y tecnolog\u00edas.\r\n\u0095 Procesos de desarrollo acad\u00e9mico enfatizan el crecimiento individual, poco claros\r\npara acad\u00e9micos.as del \u00e1rea de las artes o con enfoque en ITD. Existen diferencias\r\nde g\u00e9nero favorables a hombres en jerarquizaci\u00f3n, publicaciones y proyectos\r\nobtenidos.\r\n\u0095 Gesti\u00f3n acad\u00e9mica desarticulada entre las unidades, observ\u00e1ndose repetici\u00f3n de\r\nprocesos de gesti\u00f3n entre las unidades participantes.\r\n\u0095 Los miembros de la comunidad indican percibir lo que denominan \u0093extractivismo\r\nacad\u00e9mico\u0094, una pr\u00e1ctica acad\u00e9mica en donde el v\u00ednculo con las comunidades\r\ntermina con la recogida de datos. Adem\u00e1s, el conocimiento universitario no es de\r\nf\u00e1cil acceso.\r\nEl an\u00e1lisis y discusi\u00f3n de las consecuencias de dichas limitaciones derivaron en el\r\nplanteamiento de propuestas, que buscan generar transformaci\u00f3n en nuestros procesos\r\nacad\u00e9micos, fomentando la flexibilidad curricular, la ITD, la generaci\u00f3n de conocimientos con atenci\u00f3n al territorio y la promoci\u00f3n de la equidad entre personas y la participaci\u00f3n\r\nfemenina en roles de liderazgo. Algunas de ellas son:\r\n1. Conformar un consorcio interuniversitario en HACS de las Universidades P\u00fablicas de\r\nlas Regiones VI y VII, cuya gobernanza colaborativa promueva transformaciones en\r\nlos procesos formativos, de investigaci\u00f3n y creaci\u00f3n, vinculaci\u00f3n con el medio (VcM)\r\ny gesti\u00f3n en ambas universidades. Posee sellos espec\u00edficos en fomento del\r\npatrimonio, de salud mental y bienestar, equidad de g\u00e9nero y derechos humanos y\r\npromueve la discusi\u00f3n y desarrollo de pol\u00edticas p\u00fablicas regionales y nacionales.\r\n2. Redise\u00f1ar carreras de pregrado HACS en cada universidad, flexibles, incorporando\r\nmetodolog\u00edas ITD y problem\u00e1ticas del Valle Central, formando as\u00ed competencias de\r\ntransferencia de conocimientos para la innovaci\u00f3n social y la pol\u00edtica p\u00fablica y\r\ncultural.\r\n3. Formular e implementar programas de estudio interuniversitarios, con un modelo\r\nequivalente a los pregrados redise\u00f1ados, con foco en formaci\u00f3n continua y\r\npostgrado.\r\n4. Construir micro-certificaciones al alero de los planes de estudio de pregrado,\r\npromoviendo la flexibilidad curricular y la innovaci\u00f3n para las profesiones del futuro.\r\n5. Crear una comisi\u00f3n paritaria de g\u00e9nero, ocupada de generaci\u00f3n consorciada de\r\npropuestas y seguimiento de datos para el logro de la equidad de g\u00e9nero, abierto a\r\nla comunidad universitaria y del Valle Central.\r\n6. Constituir equipos de investigaci\u00f3n\/creaci\u00f3n con foco ITD e interuniversitario,\r\nincorporando problem\u00e1ticas del Valle Central y promoviendo la discusi\u00f3n y\r\ngeneraci\u00f3n de pol\u00edticas p\u00fablicas en las \u00e1reas de desarrollo.\r\n7. Habilitar un espacio f\u00edsico independiente a las facultades, donde las personas que se\r\nadscriben desarrollen ITD de manera abierta y colaborativa con otros acad\u00e9micos,\r\nestudiantes y\/o miembros de la sociedad civil.\r\n8. Creaci\u00f3n de una gobernanza que involucre a la comunidad acad\u00e9mica, estudiantil y\r\nde la comuna, para la ejecuci\u00f3n y asesor\u00eda de las acciones programadas, enfatizando\r\nlos sellos del proyecto y acercando las propuestas al desarrollo y logro de pol\u00edticas\r\np\u00fablicas.\r\n9. Presentar a las autoridades superiores universitarias un perfil de desarrollo de\r\nacad\u00e9micas.os HACS con \u00e9nfasis en indicadores para la jerarquizaci\u00f3n,\r\nhomologando con ello las trayectorias acad\u00e9micas en todas las disciplinas\r\nuniversitarias (especialmente artes) incorporando enfoque ITD.\r\n10.Promover la democratizaci\u00f3n del conocimiento a partir del uso de herramientas de\r\nciencia abierta, incorpor\u00e1ndolas en el desarrollo de la formaci\u00f3n, y a trav\u00e9s del uso\r\nde repositorios para el almacenamiento de informaci\u00f3n de todas las disciplinas\r\nHACS.\r\nConsideramos que los conocimientos de nuestros territorios son una oportunidad para el\r\nmejoramiento de nuestros planes de formaci\u00f3n, as\u00ed como para proponer otros nuevos que\r\narticulen las capacidades de los planteles universitarios. Esta propuesta plantea que es\r\nprioritaria la capacitaci\u00f3n docente en estrategias ITD, permitiendo con ello el abordaje de problemas relevantes para el territorio desde una perspectiva amplia. Todo lo anterior,\r\npermitir\u00e1 formar profesionales capacitados para desarrollarse en entornos complejos.\r\nEn el campo de la investigaci\u00f3n la propuesta considera la creaci\u00f3n de grupos de trabajo\r\nITD en tem\u00e1ticas espec\u00edficas de desarrollo para las HACS, enfatizando los temas de\r\nPatrimonio, Salud Mental y Bienestar, y Liderazgo de Mujeres. Estos grupos deber\u00e1n\r\npromover el liderazgo de mujeres en sus propuestas, relacionarse con su espacio de inter\u00e9s\r\ne involucrar a los actores sociales de manera activa y rec\u00edproca. El objetivo es crear, en 10\r\na\u00f1os, grupos de referencia nacional en investigaci\u00f3n b\u00e1sica, aplicada y art\u00edstica con base\r\nen ITD permitiendo, as\u00ed, sustentabilidad de las estrategias de desarrollo m\u00e1s all\u00e1 del\r\nperiodo de financiaci\u00f3n. Construir un camino de desarrollo acad\u00e9mico para las HACS,\r\nbasado en ITD y con especial atenci\u00f3n a las artes permitir\u00e1 mayor equidad disciplinar en\r\neste proceso y orientaci\u00f3n para el desarrollo, aumentando as\u00ed el valor de los conocimientos\r\ncient\u00edficos, creativos y tradicionales para la instituci\u00f3n.\r\nPretendemos construir una estrategia de VcM sustentada en conocimiento cient\u00edfico y\r\ncreativo, promoviendo con ello la innovaci\u00f3n, la transferencia y el escalamiento de\r\nproductos, en donde participa de manera activa la comunidad no acad\u00e9mica de nuestros\r\nterritorios. Es nuestro inter\u00e9s democratizar el conocimiento y abrirlo a nuestras\r\ncomunidades a trav\u00e9s de mecanismos de ciencia abierta y, por \u00faltimo, una gobernanza\r\neficiente para articular nuestros objetivos y metas, desarrollando herramientas de\r\ndiscusi\u00f3n colaborativa, seguimiento y evaluaci\u00f3n de impacto para la mejora continua.\r\nEl horizonte de desarrollo de nuestras iniciativas es de diez a\u00f1os, comprometiendo al sexto\r\na\u00f1o de ejecuci\u00f3n una serie de acciones que involucran, en ambas regiones, un\r\nacercamiento de cada instituci\u00f3n a su espacio de influencia y colaboraci\u00f3n entre ellas. As\u00ed\r\nmismo, esperamos constituir un espacio consorciado que promueve una formaci\u00f3n\r\nprofesional sensible a las necesidades del entorno y cuyos estudiantes poseen\r\ncompetencias para atenderlas en colaboraci\u00f3n con sus habitantes; que capacita a\r\nacad\u00e9micos y profesionales en mecanismos de promoci\u00f3n de la ITD; que participa en la\r\ndiscusi\u00f3n y generaci\u00f3n de pol\u00edticas p\u00fablicas; que desarrolla conocimiento ITD a trav\u00e9s de\r\ngrupos cuya investigaci\u00f3n se aplica a temas espec\u00edficos, siendo referentes a nivel nacional;\r\nque se relaciona con el entorno de manera cooperativa y bidireccional, cuyos conocimientos\r\nson la base de la innovaci\u00f3n y la transferencia. Y, por \u00faltimo, un espacio que promueve la\r\nequidad de g\u00e9nero, la participaci\u00f3n de mujeres en espacios de liderazgo y la participaci\u00f3n\r\nsocial de nuestros territorios.\r\nFinalmente, podremos configurarnos como un consorcio universitario con gran presencia\r\nen sus regiones y que desarrolle un trabajo virtuoso con diferentes actores del mundo\r\nuniversitario y de la sociedad civil, quienes asesorar\u00e1n nuestro trabajo de manera que\r\natiendan a pol\u00edticas p\u00fablicas y necesidades de los territorios.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26605\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Cambio clim\u00e1tico y econom\u00eda: an\u00e1lisis de riesgos y soluciones para sectores estrat\u00e9gicos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26605\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26605\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto \u0093Cambio clim\u00e1tico y econom\u00eda: an\u00e1lisis de riesgos y soluciones para sectores estrat\u00e9gicos\u0094 busca fortalecer las capacidades regionales de la Macrozona para enfrentar los crecientes desaf\u00edos del cambio clim\u00e1tico mediante la creaci\u00f3n de una red internacional de cooperaci\u00f3n cient\u00edfica. \r\nLa iniciativa se estructura en torno a tres ejes: la identificaci\u00f3n y cuantificaci\u00f3n de riesgos clim\u00e1ticos a nivel subregional, utilizando herramientas como im\u00e1genes satelitales, modelos de teor\u00eda de juegos y simulaciones; el an\u00e1lisis de c\u00f3mo hogares, productores y gobiernos ajustan sus decisiones ; y el fortalecimiento de capacidades mediante pasant\u00edas internacionales, talleres, formaci\u00f3n de estudiantes y la publicaci\u00f3n de resultados.\r\nUn componente central del proyecto es el intercambio de experiencias entre pa\u00edses en desarrollo, M\u00e9xico, Brasil y Chile, que comparten desaf\u00edos estructurales como alta informalidad laboral, barreras en el acceso al cr\u00e9dito y vulnerabilidad territorial frente al cambio clim\u00e1tico. Adem\u00e1s, el proyecto pone un fuerte \u00e9nfasis en la formaci\u00f3n de capital humano, incorporando a tesistas de pregrado y posgrado en todas las etapas de investigaci\u00f3n. Ellas\/os participar\u00e1n en actividades clave como dise\u00f1o de modelos, recolecci\u00f3n y an\u00e1lisis de datos, y redacci\u00f3n de informes, fortaleciendo sus competencias t\u00e9cnicas y su vinculaci\u00f3n con redes internacionales. Se ofrecer\u00e1n tambi\u00e9n un workshop y un taller, orientado a fortalecer las capacidades en temas de econom\u00eda del cambio clim\u00e1tico.\r\nParticipan la Universidad de O\u0092Higgins y la Universidad de los Andes de Chile; y como socios internacionales el Banco Central de M\u00e9xico y la Fundaci\u00f3n Getulio Vargas de Brasil. Esta colaboraci\u00f3n busca generar evidencia territorialmente situada para el dise\u00f1o de planes de resiliencia agr\u00edcola, descentralizar la formaci\u00f3n cient\u00edfica en Chile y consolidar una red duradera de investigaci\u00f3n aplicada en econom\u00eda del cambio clim\u00e1tico con impacto regional y latinoamericano.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26768\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Conocimientos 2030 Etapa 2\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26768\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26768\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las regiones de O\u0092Higgins y el Maule tienen una historia com\u00fan, caracter\u00edsticas y un\r\ndesarrollo social similar. Ambas regiones, ubicadas en el Valle Central chileno, comparten\r\nelementos culturales, s\u00edmbolos, historias y personajes que, su conjunto, reflejan la\r\nidentidad chilena. La historia de estos territorios incluye conocimiento diverso sobre\r\nnuestro pasado reciente y lejano en forma de relatos, pinturas, medios de transporte,\r\nmecanismos de comercializaci\u00f3n, oficios y manifestaciones culturales, que son comunes a\r\nellas. Debido a las importantes similitudes territoriales, humanas y productivas que poseen\r\nlas regiones de O\u0092Higgins y el Maule, es que sus universidades estatales proponen la\r\ninstitucionalizaci\u00f3n de un consorcio interuniversitario para fortalecer las Humanidades,\r\nArtes y Ciencias Sociales (HACS) en el Valle Central de Chile, transformando procesos\r\nacad\u00e9micos y generando instancias de participaci\u00f3n activa con la comunidad territorial.\r\nEste consorcio interuniversitario entre la Universidad de Talca y la Universidad de O\u0092Higgins\r\nse denomina \u0093Consorcio del Valle Central\u0094, en su af\u00e1n por ver representadas las realidades\r\ny conocimientos territoriales de la costa, del centro y de la cordillera de la VII y VI Regi\u00f3n.\r\nLa creaci\u00f3n del Consorcio Valle Central est\u00e1 sustentada en el Plan Estrat\u00e9gico para el\r\nFortalecimiento de las HACS, construido como producto de la etapa 1 de\r\nConocimientos2030. Este, a su vez, est\u00e1 basado en un diagn\u00f3stico exhaustivo que incluy\u00f3\r\nan\u00e1lisis interno, territorial (de cada provincia del Valle Central) y benchmarking con\r\ninstituciones de referencia. Como resultado, se identificaron una serie de dificultades en\r\nnuestras unidades que son relevantes para la transformaci\u00f3n de los procesos acad\u00e9micos.\r\nEntre ellas:\r\n\u0095 Rigidez de los programas formativos y uso de metodolog\u00edas encasilladas en las\r\ndisciplinas, que dificultan el an\u00e1lisis de la realidad social y p\u00fablica.\r\n\u0095 Limitada incorporaci\u00f3n de las complejidades del territorio a la formaci\u00f3n, afectando\r\nnegativamente a la relaci\u00f3n bidireccional y al desarrollo de iniciativas innovadoras.\r\n\u0095 Iniciativas acad\u00e9micas se acotan a fondos p\u00fablicos y muy competitivos, siendo\r\nexcepciones aquellos del sector privado o de inter\u00e9s p\u00fablico.\r\n\u0095 Desarrollo incipiente de la inter y transdisciplina (en adelante, ITD), e insuficiente\r\ntransferencia de conocimientos y tecnolog\u00edas.\r\n\u0095 Procesos de desarrollo acad\u00e9mico enfatizan el crecimiento individual, poco claros\r\npara acad\u00e9micos.as del \u00e1rea de las artes o con enfoque en ITD. Existen diferencias\r\nde g\u00e9nero favorables a hombres en jerarquizaci\u00f3n, publicaciones y proyectos\r\nobtenidos.\r\n\u0095 Gesti\u00f3n acad\u00e9mica desarticulada entre las unidades, observ\u00e1ndose repetici\u00f3n de\r\nprocesos de gesti\u00f3n entre las unidades participantes.\r\n\u0095 Los miembros de la comunidad indican percibir lo que denominan \u0093extractivismo\r\nacad\u00e9mico\u0094, una pr\u00e1ctica acad\u00e9mica en donde el v\u00ednculo con las comunidades\r\ntermina con la recogida de datos. Adem\u00e1s, el conocimiento universitario no es de\r\nf\u00e1cil acceso.\r\nEl an\u00e1lisis y discusi\u00f3n de las consecuencias de dichas limitaciones derivaron en el\r\nplanteamiento de propuestas, que buscan generar transformaci\u00f3n en nuestros procesos\r\nacad\u00e9micos, fomentando la flexibilidad curricular, la ITD, la generaci\u00f3n de conocimientos con atenci\u00f3n al territorio y la promoci\u00f3n de la equidad entre personas y la participaci\u00f3n\r\nfemenina en roles de liderazgo. Algunas de ellas son:\r\n1. Conformar un consorcio interuniversitario en HACS de las Universidades P\u00fablicas de\r\nlas Regiones VI y VII, cuya gobernanza colaborativa promueva transformaciones en\r\nlos procesos formativos, de investigaci\u00f3n y creaci\u00f3n, vinculaci\u00f3n con el medio (VcM)\r\ny gesti\u00f3n en ambas universidades. Posee sellos espec\u00edficos en fomento del\r\npatrimonio, de salud mental y bienestar, equidad de g\u00e9nero y derechos humanos y\r\npromueve la discusi\u00f3n y desarrollo de pol\u00edticas p\u00fablicas regionales y nacionales.\r\n2. Redise\u00f1ar carreras de pregrado HACS en cada universidad, flexibles, incorporando\r\nmetodolog\u00edas ITD y problem\u00e1ticas del Valle Central, formando as\u00ed competencias de\r\ntransferencia de conocimientos para la innovaci\u00f3n social y la pol\u00edtica p\u00fablica y\r\ncultural.\r\n3. Formular e implementar programas de estudio interuniversitarios, con un modelo\r\nequivalente a los pregrados redise\u00f1ados, con foco en formaci\u00f3n continua y\r\npostgrado.\r\n4. Construir micro-certificaciones al alero de los planes de estudio de pregrado,\r\npromoviendo la flexibilidad curricular y la innovaci\u00f3n para las profesiones del futuro.\r\n5. Crear una comisi\u00f3n paritaria de g\u00e9nero, ocupada de generaci\u00f3n consorciada de\r\npropuestas y seguimiento de datos para el logro de la equidad de g\u00e9nero, abierto a\r\nla comunidad universitaria y del Valle Central.\r\n6. Constituir equipos de investigaci\u00f3n\/creaci\u00f3n con foco ITD e interuniversitario,\r\nincorporando problem\u00e1ticas del Valle Central y promoviendo la discusi\u00f3n y\r\ngeneraci\u00f3n de pol\u00edticas p\u00fablicas en las \u00e1reas de desarrollo.\r\n7. Habilitar un espacio f\u00edsico independiente a las facultades, donde las personas que se\r\nadscriben desarrollen ITD de manera abierta y colaborativa con otros acad\u00e9micos,\r\nestudiantes y\/o miembros de la sociedad civil.\r\n8. Creaci\u00f3n de una gobernanza que involucre a la comunidad acad\u00e9mica, estudiantil y\r\nde la comuna, para la ejecuci\u00f3n y asesor\u00eda de las acciones programadas, enfatizando\r\nlos sellos del proyecto y acercando las propuestas al desarrollo y logro de pol\u00edticas\r\np\u00fablicas.\r\n9. Presentar a las autoridades superiores universitarias un perfil de desarrollo de\r\nacad\u00e9micas.os HACS con \u00e9nfasis en indicadores para la jerarquizaci\u00f3n,\r\nhomologando con ello las trayectorias acad\u00e9micas en todas las disciplinas\r\nuniversitarias (especialmente artes) incorporando enfoque ITD.\r\n10.Promover la democratizaci\u00f3n del conocimiento a partir del uso de herramientas de\r\nciencia abierta, incorpor\u00e1ndolas en el desarrollo de la formaci\u00f3n, y a trav\u00e9s del uso\r\nde repositorios para el almacenamiento de informaci\u00f3n de todas las disciplinas\r\nHACS.\r\nConsideramos que los conocimientos de nuestros territorios son una oportunidad para el\r\nmejoramiento de nuestros planes de formaci\u00f3n, as\u00ed como para proponer otros nuevos que\r\narticulen las capacidades de los planteles universitarios. Esta propuesta plantea que es\r\nprioritaria la capacitaci\u00f3n docente en estrategias ITD, permitiendo con ello el abordaje de problemas relevantes para el territorio desde una perspectiva amplia. Todo lo anterior,\r\npermitir\u00e1 formar profesionales capacitados para desarrollarse en entornos complejos.\r\nEn el campo de la investigaci\u00f3n la propuesta considera la creaci\u00f3n de grupos de trabajo\r\nITD en tem\u00e1ticas espec\u00edficas de desarrollo para las HACS, enfatizando los temas de\r\nPatrimonio, Salud Mental y Bienestar, y Liderazgo de Mujeres. Estos grupos deber\u00e1n\r\npromover el liderazgo de mujeres en sus propuestas, relacionarse con su espacio de inter\u00e9s\r\ne involucrar a los actores sociales de manera activa y rec\u00edproca. El objetivo es crear, en 10\r\na\u00f1os, grupos de referencia nacional en investigaci\u00f3n b\u00e1sica, aplicada y art\u00edstica con base\r\nen ITD permitiendo, as\u00ed, sustentabilidad de las estrategias de desarrollo m\u00e1s all\u00e1 del\r\nperiodo de financiaci\u00f3n. Construir un camino de desarrollo acad\u00e9mico para las HACS,\r\nbasado en ITD y con especial atenci\u00f3n a las artes permitir\u00e1 mayor equidad disciplinar en\r\neste proceso y orientaci\u00f3n para el desarrollo, aumentando as\u00ed el valor de los conocimientos\r\ncient\u00edficos, creativos y tradicionales para la instituci\u00f3n.\r\nPretendemos construir una estrategia de VcM sustentada en conocimiento cient\u00edfico y\r\ncreativo, promoviendo con ello la innovaci\u00f3n, la transferencia y el escalamiento de\r\nproductos, en donde participa de manera activa la comunidad no acad\u00e9mica de nuestros\r\nterritorios. Es nuestro inter\u00e9s democratizar el conocimiento y abrirlo a nuestras\r\ncomunidades a trav\u00e9s de mecanismos de ciencia abierta y, por \u00faltimo, una gobernanza\r\neficiente para articular nuestros objetivos y metas, desarrollando herramientas de\r\ndiscusi\u00f3n colaborativa, seguimiento y evaluaci\u00f3n de impacto para la mejora continua.\r\nEl horizonte de desarrollo de nuestras iniciativas es de diez a\u00f1os, comprometiendo al sexto\r\na\u00f1o de ejecuci\u00f3n una serie de acciones que involucran, en ambas regiones, un\r\nacercamiento de cada instituci\u00f3n a su espacio de influencia y colaboraci\u00f3n entre ellas. As\u00ed\r\nmismo, esperamos constituir un espacio consorciado que promueve una formaci\u00f3n\r\nprofesional sensible a las necesidades del entorno y cuyos estudiantes poseen\r\ncompetencias para atenderlas en colaboraci\u00f3n con sus habitantes; que capacita a\r\nacad\u00e9micos y profesionales en mecanismos de promoci\u00f3n de la ITD; que participa en la\r\ndiscusi\u00f3n y generaci\u00f3n de pol\u00edticas p\u00fablicas; que desarrolla conocimiento ITD a trav\u00e9s de\r\ngrupos cuya investigaci\u00f3n se aplica a temas espec\u00edficos, siendo referentes a nivel nacional;\r\nque se relaciona con el entorno de manera cooperativa y bidireccional, cuyos conocimientos\r\nson la base de la innovaci\u00f3n y la transferencia. Y, por \u00faltimo, un espacio que promueve la\r\nequidad de g\u00e9nero, la participaci\u00f3n de mujeres en espacios de liderazgo y la participaci\u00f3n\r\nsocial de nuestros territorios.\r\nFinalmente, podremos configurarnos como un consorcio universitario con gran presencia\r\nen sus regiones y que desarrolle un trabajo virtuoso con diferentes actores del mundo\r\nuniversitario y de la sociedad civil, quienes asesorar\u00e1n nuestro trabajo de manera que\r\natiendan a pol\u00edticas p\u00fablicas y necesidades de los territorios.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26921\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Conocimientos 2030 Etapa 2\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26921\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26921\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las regiones de O\u0092Higgins y el Maule tienen una historia com\u00fan, caracter\u00edsticas y un\r\ndesarrollo social similar. Ambas regiones, ubicadas en el Valle Central chileno, comparten\r\nelementos culturales, s\u00edmbolos, historias y personajes que, su conjunto, reflejan la\r\nidentidad chilena. La historia de estos territorios incluye conocimiento diverso sobre\r\nnuestro pasado reciente y lejano en forma de relatos, pinturas, medios de transporte,\r\nmecanismos de comercializaci\u00f3n, oficios y manifestaciones culturales, que son comunes a\r\nellas. Debido a las importantes similitudes territoriales, humanas y productivas que poseen\r\nlas regiones de O\u0092Higgins y el Maule, es que sus universidades estatales proponen la\r\ninstitucionalizaci\u00f3n de un consorcio interuniversitario para fortalecer las Humanidades,\r\nArtes y Ciencias Sociales (HACS) en el Valle Central de Chile, transformando procesos\r\nacad\u00e9micos y generando instancias de participaci\u00f3n activa con la comunidad territorial.\r\nEste consorcio interuniversitario entre la Universidad de Talca y la Universidad de O\u0092Higgins\r\nse denomina \u0093Consorcio del Valle Central\u0094, en su af\u00e1n por ver representadas las realidades\r\ny conocimientos territoriales de la costa, del centro y de la cordillera de la VII y VI Regi\u00f3n.\r\nLa creaci\u00f3n del Consorcio Valle Central est\u00e1 sustentada en el Plan Estrat\u00e9gico para el\r\nFortalecimiento de las HACS, construido como producto de la etapa 1 de\r\nConocimientos2030. Este, a su vez, est\u00e1 basado en un diagn\u00f3stico exhaustivo que incluy\u00f3\r\nan\u00e1lisis interno, territorial (de cada provincia del Valle Central) y benchmarking con\r\ninstituciones de referencia. Como resultado, se identificaron una serie de dificultades en\r\nnuestras unidades que son relevantes para la transformaci\u00f3n de los procesos acad\u00e9micos.\r\nEntre ellas:\r\n\u0095 Rigidez de los programas formativos y uso de metodolog\u00edas encasilladas en las\r\ndisciplinas, que dificultan el an\u00e1lisis de la realidad social y p\u00fablica.\r\n\u0095 Limitada incorporaci\u00f3n de las complejidades del territorio a la formaci\u00f3n, afectando\r\nnegativamente a la relaci\u00f3n bidireccional y al desarrollo de iniciativas innovadoras.\r\n\u0095 Iniciativas acad\u00e9micas se acotan a fondos p\u00fablicos y muy competitivos, siendo\r\nexcepciones aquellos del sector privado o de inter\u00e9s p\u00fablico.\r\n\u0095 Desarrollo incipiente de la inter y transdisciplina (en adelante, ITD), e insuficiente\r\ntransferencia de conocimientos y tecnolog\u00edas.\r\n\u0095 Procesos de desarrollo acad\u00e9mico enfatizan el crecimiento individual, poco claros\r\npara acad\u00e9micos.as del \u00e1rea de las artes o con enfoque en ITD. Existen diferencias\r\nde g\u00e9nero favorables a hombres en jerarquizaci\u00f3n, publicaciones y proyectos\r\nobtenidos.\r\n\u0095 Gesti\u00f3n acad\u00e9mica desarticulada entre las unidades, observ\u00e1ndose repetici\u00f3n de\r\nprocesos de gesti\u00f3n entre las unidades participantes.\r\n\u0095 Los miembros de la comunidad indican percibir lo que denominan \u0093extractivismo\r\nacad\u00e9mico\u0094, una pr\u00e1ctica acad\u00e9mica en donde el v\u00ednculo con las comunidades\r\ntermina con la recogida de datos. Adem\u00e1s, el conocimiento universitario no es de\r\nf\u00e1cil acceso.\r\nEl an\u00e1lisis y discusi\u00f3n de las consecuencias de dichas limitaciones derivaron en el\r\nplanteamiento de propuestas, que buscan generar transformaci\u00f3n en nuestros procesos\r\nacad\u00e9micos, fomentando la flexibilidad curricular, la ITD, la generaci\u00f3n de conocimientos con atenci\u00f3n al territorio y la promoci\u00f3n de la equidad entre personas y la participaci\u00f3n\r\nfemenina en roles de liderazgo. Algunas de ellas son:\r\n1. Conformar un consorcio interuniversitario en HACS de las Universidades P\u00fablicas de\r\nlas Regiones VI y VII, cuya gobernanza colaborativa promueva transformaciones en\r\nlos procesos formativos, de investigaci\u00f3n y creaci\u00f3n, vinculaci\u00f3n con el medio (VcM)\r\ny gesti\u00f3n en ambas universidades. Posee sellos espec\u00edficos en fomento del\r\npatrimonio, de salud mental y bienestar, equidad de g\u00e9nero y derechos humanos y\r\npromueve la discusi\u00f3n y desarrollo de pol\u00edticas p\u00fablicas regionales y nacionales.\r\n2. Redise\u00f1ar carreras de pregrado HACS en cada universidad, flexibles, incorporando\r\nmetodolog\u00edas ITD y problem\u00e1ticas del Valle Central, formando as\u00ed competencias de\r\ntransferencia de conocimientos para la innovaci\u00f3n social y la pol\u00edtica p\u00fablica y\r\ncultural.\r\n3. Formular e implementar programas de estudio interuniversitarios, con un modelo\r\nequivalente a los pregrados redise\u00f1ados, con foco en formaci\u00f3n continua y\r\npostgrado.\r\n4. Construir micro-certificaciones al alero de los planes de estudio de pregrado,\r\npromoviendo la flexibilidad curricular y la innovaci\u00f3n para las profesiones del futuro.\r\n5. Crear una comisi\u00f3n paritaria de g\u00e9nero, ocupada de generaci\u00f3n consorciada de\r\npropuestas y seguimiento de datos para el logro de la equidad de g\u00e9nero, abierto a\r\nla comunidad universitaria y del Valle Central.\r\n6. Constituir equipos de investigaci\u00f3n\/creaci\u00f3n con foco ITD e interuniversitario,\r\nincorporando problem\u00e1ticas del Valle Central y promoviendo la discusi\u00f3n y\r\ngeneraci\u00f3n de pol\u00edticas p\u00fablicas en las \u00e1reas de desarrollo.\r\n7. Habilitar un espacio f\u00edsico independiente a las facultades, donde las personas que se\r\nadscriben desarrollen ITD de manera abierta y colaborativa con otros acad\u00e9micos,\r\nestudiantes y\/o miembros de la sociedad civil.\r\n8. Creaci\u00f3n de una gobernanza que involucre a la comunidad acad\u00e9mica, estudiantil y\r\nde la comuna, para la ejecuci\u00f3n y asesor\u00eda de las acciones programadas, enfatizando\r\nlos sellos del proyecto y acercando las propuestas al desarrollo y logro de pol\u00edticas\r\np\u00fablicas.\r\n9. Presentar a las autoridades superiores universitarias un perfil de desarrollo de\r\nacad\u00e9micas.os HACS con \u00e9nfasis en indicadores para la jerarquizaci\u00f3n,\r\nhomologando con ello las trayectorias acad\u00e9micas en todas las disciplinas\r\nuniversitarias (especialmente artes) incorporando enfoque ITD.\r\n10.Promover la democratizaci\u00f3n del conocimiento a partir del uso de herramientas de\r\nciencia abierta, incorpor\u00e1ndolas en el desarrollo de la formaci\u00f3n, y a trav\u00e9s del uso\r\nde repositorios para el almacenamiento de informaci\u00f3n de todas las disciplinas\r\nHACS.\r\nConsideramos que los conocimientos de nuestros territorios son una oportunidad para el\r\nmejoramiento de nuestros planes de formaci\u00f3n, as\u00ed como para proponer otros nuevos que\r\narticulen las capacidades de los planteles universitarios. Esta propuesta plantea que es\r\nprioritaria la capacitaci\u00f3n docente en estrategias ITD, permitiendo con ello el abordaje de problemas relevantes para el territorio desde una perspectiva amplia. Todo lo anterior,\r\npermitir\u00e1 formar profesionales capacitados para desarrollarse en entornos complejos.\r\nEn el campo de la investigaci\u00f3n la propuesta considera la creaci\u00f3n de grupos de trabajo\r\nITD en tem\u00e1ticas espec\u00edficas de desarrollo para las HACS, enfatizando los temas de\r\nPatrimonio, Salud Mental y Bienestar, y Liderazgo de Mujeres. Estos grupos deber\u00e1n\r\npromover el liderazgo de mujeres en sus propuestas, relacionarse con su espacio de inter\u00e9s\r\ne involucrar a los actores sociales de manera activa y rec\u00edproca. El objetivo es crear, en 10\r\na\u00f1os, grupos de referencia nacional en investigaci\u00f3n b\u00e1sica, aplicada y art\u00edstica con base\r\nen ITD permitiendo, as\u00ed, sustentabilidad de las estrategias de desarrollo m\u00e1s all\u00e1 del\r\nperiodo de financiaci\u00f3n. Construir un camino de desarrollo acad\u00e9mico para las HACS,\r\nbasado en ITD y con especial atenci\u00f3n a las artes permitir\u00e1 mayor equidad disciplinar en\r\neste proceso y orientaci\u00f3n para el desarrollo, aumentando as\u00ed el valor de los conocimientos\r\ncient\u00edficos, creativos y tradicionales para la instituci\u00f3n.\r\nPretendemos construir una estrategia de VcM sustentada en conocimiento cient\u00edfico y\r\ncreativo, promoviendo con ello la innovaci\u00f3n, la transferencia y el escalamiento de\r\nproductos, en donde participa de manera activa la comunidad no acad\u00e9mica de nuestros\r\nterritorios. Es nuestro inter\u00e9s democratizar el conocimiento y abrirlo a nuestras\r\ncomunidades a trav\u00e9s de mecanismos de ciencia abierta y, por \u00faltimo, una gobernanza\r\neficiente para articular nuestros objetivos y metas, desarrollando herramientas de\r\ndiscusi\u00f3n colaborativa, seguimiento y evaluaci\u00f3n de impacto para la mejora continua.\r\nEl horizonte de desarrollo de nuestras iniciativas es de diez a\u00f1os, comprometiendo al sexto\r\na\u00f1o de ejecuci\u00f3n una serie de acciones que involucran, en ambas regiones, un\r\nacercamiento de cada instituci\u00f3n a su espacio de influencia y colaboraci\u00f3n entre ellas. As\u00ed\r\nmismo, esperamos constituir un espacio consorciado que promueve una formaci\u00f3n\r\nprofesional sensible a las necesidades del entorno y cuyos estudiantes poseen\r\ncompetencias para atenderlas en colaboraci\u00f3n con sus habitantes; que capacita a\r\nacad\u00e9micos y profesionales en mecanismos de promoci\u00f3n de la ITD; que participa en la\r\ndiscusi\u00f3n y generaci\u00f3n de pol\u00edticas p\u00fablicas; que desarrolla conocimiento ITD a trav\u00e9s de\r\ngrupos cuya investigaci\u00f3n se aplica a temas espec\u00edficos, siendo referentes a nivel nacional;\r\nque se relaciona con el entorno de manera cooperativa y bidireccional, cuyos conocimientos\r\nson la base de la innovaci\u00f3n y la transferencia. Y, por \u00faltimo, un espacio que promueve la\r\nequidad de g\u00e9nero, la participaci\u00f3n de mujeres en espacios de liderazgo y la participaci\u00f3n\r\nsocial de nuestros territorios.\r\nFinalmente, podremos configurarnos como un consorcio universitario con gran presencia\r\nen sus regiones y que desarrolle un trabajo virtuoso con diferentes actores del mundo\r\nuniversitario y de la sociedad civil, quienes asesorar\u00e1n nuestro trabajo de manera que\r\natiendan a pol\u00edticas p\u00fablicas y necesidades de los territorios.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> PID2024-157106NB-I00<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Estatal de Investigaci\u00f3n (Espa\u00f1a)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26980\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            CONOCIMIENTO PROFESIONAL DE FUTUROS MAESTROS DE EDUCACION PRIMARIA PARA ABORDAR EL SENTIDO ALGEBRAICO\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26980\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26980\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto aborda los siguientes objetivos generales:\r\nOG1. Describir la presencia del \u00e1lgebra escolar en los documentos curriculares de educaci\u00f3n primaria\r\ny en la formaci\u00f3n de docentes de educaci\u00f3n primaria.\r\nOG2. Describir el conocimiento profesional sobre \u00e1lgebra escolar que tienen los profesores de\r\neducaci\u00f3n primaria en formaci\u00f3n\r\nOG3. Producir materiales, tareas y estrategias formativas que ayuden al profesorado al desarrollo del\r\npensamiento algebraico en primaria y a la superaci\u00f3n de los posibles obst\u00e1culos de aprendizaje.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2025 - Octubre 2029<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Estatal de Investigaci\u00f3n (Espa\u00f1a)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26981\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desarrollo de Conocimiento y Competencias para la ense\u00f1anza de la resoluci\u00f3n y formulaci\u00f3n de problemas matem\u00e1ticos en formaci\u00f3n inicial de profesorado (MTSK&#038;C-RFPM)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26981\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26981\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto aborda los siguientes objetivos generales:\r\nOG1. Conceptualizar procesos de desarrollo de conocimiento y competencias docentes en planificaci\u00f3n\r\ny gesti\u00f3n de la ense\u00f1anza de la resoluci\u00f3n y formulaci\u00f3n de problemas matem\u00e1ticos.\r\nOG2. Identificar buenas pr\u00e1cticas en la planificaci\u00f3n y gesti\u00f3n de la ense\u00f1anza de la resoluci\u00f3n y\r\nformulaci\u00f3n de problemas matem\u00e1ticos.\r\nOG3. Producir secuencias de tareas (con base te\u00f3rica y contrastadas emp\u00edricamente) que promuevan el\r\ndesarrollo de conocimiento y competencias docentes en planificaci\u00f3n y gesti\u00f3n de la ense\u00f1anza de la\r\nresoluci\u00f3n y formulaci\u00f3n de problemas matem\u00e1ticos.\r\nOG4. Difundir los resultados de la investigaci\u00f3n a la comunidad acad\u00e9mica y cient\u00edfica y transferirlos a\r\nlos colectivos profesionales interesados en los resultados.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26995\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Conocimientos 2030 Etapa 2\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26995\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26995\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las regiones de O\u0092Higgins y el Maule tienen una historia com\u00fan, caracter\u00edsticas y un\r\ndesarrollo social similar. Ambas regiones, ubicadas en el Valle Central chileno, comparten\r\nelementos culturales, s\u00edmbolos, historias y personajes que, su conjunto, reflejan la\r\nidentidad chilena. La historia de estos territorios incluye conocimiento diverso sobre\r\nnuestro pasado reciente y lejano en forma de relatos, pinturas, medios de transporte,\r\nmecanismos de comercializaci\u00f3n, oficios y manifestaciones culturales, que son comunes a\r\nellas. Debido a las importantes similitudes territoriales, humanas y productivas que poseen\r\nlas regiones de O\u0092Higgins y el Maule, es que sus universidades estatales proponen la\r\ninstitucionalizaci\u00f3n de un consorcio interuniversitario para fortalecer las Humanidades,\r\nArtes y Ciencias Sociales (HACS) en el Valle Central de Chile, transformando procesos\r\nacad\u00e9micos y generando instancias de participaci\u00f3n activa con la comunidad territorial.\r\nEste consorcio interuniversitario entre la Universidad de Talca y la Universidad de O\u0092Higgins\r\nse denomina \u0093Consorcio del Valle Central\u0094, en su af\u00e1n por ver representadas las realidades\r\ny conocimientos territoriales de la costa, del centro y de la cordillera de la VII y VI Regi\u00f3n.\r\nLa creaci\u00f3n del Consorcio Valle Central est\u00e1 sustentada en el Plan Estrat\u00e9gico para el\r\nFortalecimiento de las HACS, construido como producto de la etapa 1 de\r\nConocimientos2030. Este, a su vez, est\u00e1 basado en un diagn\u00f3stico exhaustivo que incluy\u00f3\r\nan\u00e1lisis interno, territorial (de cada provincia del Valle Central) y benchmarking con\r\ninstituciones de referencia. Como resultado, se identificaron una serie de dificultades en\r\nnuestras unidades que son relevantes para la transformaci\u00f3n de los procesos acad\u00e9micos.\r\nEntre ellas:\r\n\u0095 Rigidez de los programas formativos y uso de metodolog\u00edas encasilladas en las\r\ndisciplinas, que dificultan el an\u00e1lisis de la realidad social y p\u00fablica.\r\n\u0095 Limitada incorporaci\u00f3n de las complejidades del territorio a la formaci\u00f3n, afectando\r\nnegativamente a la relaci\u00f3n bidireccional y al desarrollo de iniciativas innovadoras.\r\n\u0095 Iniciativas acad\u00e9micas se acotan a fondos p\u00fablicos y muy competitivos, siendo\r\nexcepciones aquellos del sector privado o de inter\u00e9s p\u00fablico.\r\n\u0095 Desarrollo incipiente de la inter y transdisciplina (en adelante, ITD), e insuficiente\r\ntransferencia de conocimientos y tecnolog\u00edas.\r\n\u0095 Procesos de desarrollo acad\u00e9mico enfatizan el crecimiento individual, poco claros\r\npara acad\u00e9micos.as del \u00e1rea de las artes o con enfoque en ITD. Existen diferencias\r\nde g\u00e9nero favorables a hombres en jerarquizaci\u00f3n, publicaciones y proyectos\r\nobtenidos.\r\n\u0095 Gesti\u00f3n acad\u00e9mica desarticulada entre las unidades, observ\u00e1ndose repetici\u00f3n de\r\nprocesos de gesti\u00f3n entre las unidades participantes.\r\n\u0095 Los miembros de la comunidad indican percibir lo que denominan \u0093extractivismo\r\nacad\u00e9mico\u0094, una pr\u00e1ctica acad\u00e9mica en donde el v\u00ednculo con las comunidades\r\ntermina con la recogida de datos. Adem\u00e1s, el conocimiento universitario no es de\r\nf\u00e1cil acceso.\r\nEl an\u00e1lisis y discusi\u00f3n de las consecuencias de dichas limitaciones derivaron en el\r\nplanteamiento de propuestas, que buscan generar transformaci\u00f3n en nuestros procesos\r\nacad\u00e9micos, fomentando la flexibilidad curricular, la ITD, la generaci\u00f3n de conocimientos con atenci\u00f3n al territorio y la promoci\u00f3n de la equidad entre personas y la participaci\u00f3n\r\nfemenina en roles de liderazgo. Algunas de ellas son:\r\n1. Conformar un consorcio interuniversitario en HACS de las Universidades P\u00fablicas de\r\nlas Regiones VI y VII, cuya gobernanza colaborativa promueva transformaciones en\r\nlos procesos formativos, de investigaci\u00f3n y creaci\u00f3n, vinculaci\u00f3n con el medio (VcM)\r\ny gesti\u00f3n en ambas universidades. Posee sellos espec\u00edficos en fomento del\r\npatrimonio, de salud mental y bienestar, equidad de g\u00e9nero y derechos humanos y\r\npromueve la discusi\u00f3n y desarrollo de pol\u00edticas p\u00fablicas regionales y nacionales.\r\n2. Redise\u00f1ar carreras de pregrado HACS en cada universidad, flexibles, incorporando\r\nmetodolog\u00edas ITD y problem\u00e1ticas del Valle Central, formando as\u00ed competencias de\r\ntransferencia de conocimientos para la innovaci\u00f3n social y la pol\u00edtica p\u00fablica y\r\ncultural.\r\n3. Formular e implementar programas de estudio interuniversitarios, con un modelo\r\nequivalente a los pregrados redise\u00f1ados, con foco en formaci\u00f3n continua y\r\npostgrado.\r\n4. Construir micro-certificaciones al alero de los planes de estudio de pregrado,\r\npromoviendo la flexibilidad curricular y la innovaci\u00f3n para las profesiones del futuro.\r\n5. Crear una comisi\u00f3n paritaria de g\u00e9nero, ocupada de generaci\u00f3n consorciada de\r\npropuestas y seguimiento de datos para el logro de la equidad de g\u00e9nero, abierto a\r\nla comunidad universitaria y del Valle Central.\r\n6. Constituir equipos de investigaci\u00f3n\/creaci\u00f3n con foco ITD e interuniversitario,\r\nincorporando problem\u00e1ticas del Valle Central y promoviendo la discusi\u00f3n y\r\ngeneraci\u00f3n de pol\u00edticas p\u00fablicas en las \u00e1reas de desarrollo.\r\n7. Habilitar un espacio f\u00edsico independiente a las facultades, donde las personas que se\r\nadscriben desarrollen ITD de manera abierta y colaborativa con otros acad\u00e9micos,\r\nestudiantes y\/o miembros de la sociedad civil.\r\n8. Creaci\u00f3n de una gobernanza que involucre a la comunidad acad\u00e9mica, estudiantil y\r\nde la comuna, para la ejecuci\u00f3n y asesor\u00eda de las acciones programadas, enfatizando\r\nlos sellos del proyecto y acercando las propuestas al desarrollo y logro de pol\u00edticas\r\np\u00fablicas.\r\n9. Presentar a las autoridades superiores universitarias un perfil de desarrollo de\r\nacad\u00e9micas.os HACS con \u00e9nfasis en indicadores para la jerarquizaci\u00f3n,\r\nhomologando con ello las trayectorias acad\u00e9micas en todas las disciplinas\r\nuniversitarias (especialmente artes) incorporando enfoque ITD.\r\n10.Promover la democratizaci\u00f3n del conocimiento a partir del uso de herramientas de\r\nciencia abierta, incorpor\u00e1ndolas en el desarrollo de la formaci\u00f3n, y a trav\u00e9s del uso\r\nde repositorios para el almacenamiento de informaci\u00f3n de todas las disciplinas\r\nHACS.\r\nConsideramos que los conocimientos de nuestros territorios son una oportunidad para el\r\nmejoramiento de nuestros planes de formaci\u00f3n, as\u00ed como para proponer otros nuevos que\r\narticulen las capacidades de los planteles universitarios. Esta propuesta plantea que es\r\nprioritaria la capacitaci\u00f3n docente en estrategias ITD, permitiendo con ello el abordaje de problemas relevantes para el territorio desde una perspectiva amplia. Todo lo anterior,\r\npermitir\u00e1 formar profesionales capacitados para desarrollarse en entornos complejos.\r\nEn el campo de la investigaci\u00f3n la propuesta considera la creaci\u00f3n de grupos de trabajo\r\nITD en tem\u00e1ticas espec\u00edficas de desarrollo para las HACS, enfatizando los temas de\r\nPatrimonio, Salud Mental y Bienestar, y Liderazgo de Mujeres. Estos grupos deber\u00e1n\r\npromover el liderazgo de mujeres en sus propuestas, relacionarse con su espacio de inter\u00e9s\r\ne involucrar a los actores sociales de manera activa y rec\u00edproca. El objetivo es crear, en 10\r\na\u00f1os, grupos de referencia nacional en investigaci\u00f3n b\u00e1sica, aplicada y art\u00edstica con base\r\nen ITD permitiendo, as\u00ed, sustentabilidad de las estrategias de desarrollo m\u00e1s all\u00e1 del\r\nperiodo de financiaci\u00f3n. Construir un camino de desarrollo acad\u00e9mico para las HACS,\r\nbasado en ITD y con especial atenci\u00f3n a las artes permitir\u00e1 mayor equidad disciplinar en\r\neste proceso y orientaci\u00f3n para el desarrollo, aumentando as\u00ed el valor de los conocimientos\r\ncient\u00edficos, creativos y tradicionales para la instituci\u00f3n.\r\nPretendemos construir una estrategia de VcM sustentada en conocimiento cient\u00edfico y\r\ncreativo, promoviendo con ello la innovaci\u00f3n, la transferencia y el escalamiento de\r\nproductos, en donde participa de manera activa la comunidad no acad\u00e9mica de nuestros\r\nterritorios. Es nuestro inter\u00e9s democratizar el conocimiento y abrirlo a nuestras\r\ncomunidades a trav\u00e9s de mecanismos de ciencia abierta y, por \u00faltimo, una gobernanza\r\neficiente para articular nuestros objetivos y metas, desarrollando herramientas de\r\ndiscusi\u00f3n colaborativa, seguimiento y evaluaci\u00f3n de impacto para la mejora continua.\r\nEl horizonte de desarrollo de nuestras iniciativas es de diez a\u00f1os, comprometiendo al sexto\r\na\u00f1o de ejecuci\u00f3n una serie de acciones que involucran, en ambas regiones, un\r\nacercamiento de cada instituci\u00f3n a su espacio de influencia y colaboraci\u00f3n entre ellas. As\u00ed\r\nmismo, esperamos constituir un espacio consorciado que promueve una formaci\u00f3n\r\nprofesional sensible a las necesidades del entorno y cuyos estudiantes poseen\r\ncompetencias para atenderlas en colaboraci\u00f3n con sus habitantes; que capacita a\r\nacad\u00e9micos y profesionales en mecanismos de promoci\u00f3n de la ITD; que participa en la\r\ndiscusi\u00f3n y generaci\u00f3n de pol\u00edticas p\u00fablicas; que desarrolla conocimiento ITD a trav\u00e9s de\r\ngrupos cuya investigaci\u00f3n se aplica a temas espec\u00edficos, siendo referentes a nivel nacional;\r\nque se relaciona con el entorno de manera cooperativa y bidireccional, cuyos conocimientos\r\nson la base de la innovaci\u00f3n y la transferencia. Y, por \u00faltimo, un espacio que promueve la\r\nequidad de g\u00e9nero, la participaci\u00f3n de mujeres en espacios de liderazgo y la participaci\u00f3n\r\nsocial de nuestros territorios.\r\nFinalmente, podremos configurarnos como un consorcio universitario con gran presencia\r\nen sus regiones y que desarrolle un trabajo virtuoso con diferentes actores del mundo\r\nuniversitario y de la sociedad civil, quienes asesorar\u00e1n nuestro trabajo de manera que\r\natiendan a pol\u00edticas p\u00fablicas y necesidades de los territorios.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2025 - Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Fundaci\u00f3n Palarq<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26154\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Primeros pasos humanos en Am\u00e9rica del Sur: caminando entre Gonfoterios\u0094 \u0096 Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26154\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26154\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Excavaciones arqueol\u00f3gicas y paleontol\u00f3gicas del antiguo Lago Tagua Tagua[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 13250033<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2025 - Septiembre 2029<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26704\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26704\" aria-expanded=\"false\" aria-controls=\"collapse-26704\">\n                                            A new look at human innovation: decoding the brainwaves and behaviors behind breakthroughs\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26704\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26704\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]and aligning designs with user needs (Dalton & Kahute, 2016).\r\nExamining the brain to study the dynamics of innovation: Certain psychological traits may predict innovation\r\npotential, but they often fail to capture the ongoing nature of the creative process. The emerging field of neuro-\r\ndesign integrates cognitive psychology and neuroscience to address this complexity. For example, EEG studies\r\nhave associated changes in frequency bands, such as the alpha band, with distinct experiences across various\r\ndesign stages (Cao et al., 2021; Jia & Zeng, 2021). Beyond individual processes, there is growing interest in\r\nstudying dyads and groups. In part supported by research that underscores the advantages of cognitive\r\ndiversity and the role of collective intelligence in predicting group performance in problem-solving (Sulik et al.,\r\n2022), researchers have promoted the use of hyperscanning, a method that captures simultaneous brain\r\nactivity to investigate interactions (Zamm et al., 2024). Hyperscanning offers valuable insights into the dynamics\r\nof joint action, with inter-brain synchrony (IBS) quantified through various metrics. Although few hyperscanning\r\nstudies have focused on technological innovation, some have explored creative problem-solving, revealing\r\nincreased IBS across brain regions (Balters et al., 2023). In problem-solving contexts, EEG hyperscanning has\r\ndemonstrated correlations between IBS - particularly alpha phase-locking - and performance, as well as distinct\r\nIBS patterns associated with different types of interactions (Antonenko et al., 2019; L\u00e9n\u00e9 et al., 2021)\r\nCreating prototypes of practical tools: This project explores innovation dynamics in individual and pair contexts,\r\ncombining cognitive, socio-cognitive, and physiological data. Even though this project is a basic science\r\nproposal on the psychobiological basis of human innovation, we propose creating a prototype of an AI tool for\r\nteam optimization, another for performance prediction, and an EEG neurofeedback system. Collectively, these\r\ntools aim to advance theoretical understanding while offering practical solutions that could be scaled, in further\r\nprojects, to enhance individual and collaborative innovation.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27065\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Sistema integrado de hidropon\u00eda vertical con biofiltro a base de biochar para la gesti\u00f3n sostenible de subproductos de la industria porcina\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27065\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27065\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El crecimiento poblacional, la urbanizaci\u00f3n y el aumento de residuos org\u00e1nicos agroindustriales generan presi\u00f3n sobre los ecosistemas y problemas de contaminaci\u00f3n. Para enfrentar esto, se propone valorizar estos residuos mediante la producci\u00f3n de bioinsumos como biofertilizantes, bioestimulantes y enmiendas ricas en carbono, entre ellas el biochar. El biochar es un material carbonoso obtenido por pir\u00f3lisis (300\u0096700 \u00b0C) con alta superficie espec\u00edfica, porosidad y grupos funcionales que lo hacen atractivo para usos agr\u00edcolas e industriales. Su activaci\u00f3n qu\u00edmica con KOH, NaOH y FeSO&#8324; mejora a\u00fan m\u00e1s su estructura porosa, capacidad de adsorci\u00f3n y agrega sitios de \u00f3xidos de hierro que favorecen la quimisorci\u00f3n de CO&#8322; y otros compuestos, lo que abre posibilidades para el tratamiento de aguas residuales y subproductos de distintas industrias, incluyendo la porcina.\r\n\r\nEn paralelo, el cambio clim\u00e1tico y la escasez de recursos impulsan el desarrollo de sistemas de agricultura urbana m\u00e1s eficientes, como la hidropon\u00eda y, espec\u00edficamente, la biopon\u00eda, donde los nutrientes provienen de la mineralizaci\u00f3n de materia org\u00e1nica en lugar de fertilizantes sint\u00e9ticos. Estudios previos han mostrado que el uso de digestatos y purines animales en sistemas biofiltros, combinados con biochar, puede aumentar el rendimiento de cultivos de lechuga, mejorar la solubilizaci\u00f3n de f\u00f3sforo, reducir p\u00e9rdidas de nitr\u00f3geno y disminuir la acumulaci\u00f3n de metales pesados en el agua y en los tejidos vegetales. Sin embargo, la integraci\u00f3n de biochar activado qu\u00edmicamente como biofiltro en sistemas biop\u00f3nicos que usan residuos porcinos a\u00fan est\u00e1 poco explorada.\r\n\r\nBajo este contexto, el proyecto plantea la hip\u00f3tesis de que un sistema biop\u00f3nico que utilice biochar activado con KOH, NaOH y FeSO&#8324; podr\u00e1 depurar eficientemente subproductos l\u00edquidos de la industria porcina, generando soluciones nutritivas aptas para el cultivo hidrop\u00f3nico de Lactuca sativa en torres verticales, con rendimientos comparables a soluciones minerales convencionales. El objetivo general es dise\u00f1ar, implementar y evaluar este sistema de biopon\u00eda con biofiltros de biochar activado para aclarar subproductos porcinos y usarlos en hidropon\u00eda de lechuga en sistemas verticales[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> PNTE2505<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2025 - Agosto 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27015\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27015\" aria-expanded=\"false\" aria-controls=\"collapse-27015\">\n                                            Impacto de la aplicaci\u00f3n de Silicio en el equilibrio nutricional y los par\u00e1metros productivos de plantas de ma\u00edz cultivadas con exceso de fertilizante nitrogenado en la regi\u00f3n de O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27015\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27015\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La creciente demanda mundial de alimentos, impulsada por el aumento sostenido de la poblaci\u00f3n humana, exige una producci\u00f3n agr\u00edcola eficiente y sostenible. En este contexto, los fertilizantes qu\u00edmicos han sido ampliamente utilizados para aumentar la productividad, aunque muchas veces en dosis excesivas. Este uso intensivo ha generado impactos negativos, como la emisi\u00f3n de gases de efecto invernadero (particularmente \u00f3xido nitroso, N&#8322;O), la lixiviaci\u00f3n de nutrientes y la contaminaci\u00f3n de acu\u00edferos. Adem\u00e1s, los fertilizantes representan un costo considerable, afectando la sostenibilidad econ\u00f3mica a mediano y largo plazo. El sector agr\u00edcola enfrenta presiones adicionales derivadas del cambio clim\u00e1tico, como el aumento de temperaturas, la sequ\u00eda, la toxicidad por metales pesados y desequilibrios nutricionales, los cuales afectan la calidad y el rendimiento de los cultivos. En particular, la regi\u00f3n de O\u0092Higgins es una de las principales zonas productoras de ma\u00edz en Chile y enfrenta desaf\u00edos derivados del uso excesivo de fertilizantes nitrogenados, lo que no solo eleva los costos productivos, sino que tambi\u00e9n compromete la salud medioambiental. Este proyecto tiene como objetivo principal evaluar el impacto de la aplicaci\u00f3n de silicio (Si) sobre el equilibrio nutricional y los par\u00e1metros productivos de plantas de ma\u00edz cultivadas bajo condiciones de exceso de nitr\u00f3geno. La hip\u00f3tesis central es que el silicio puede mejorar la homeostasis estequiom\u00e9trica elemental C:N:P, reducir los efectos negativos del exceso de nitr\u00f3geno y promover una mayor eficiencia en el uso de fertilizantes. Se propone adem\u00e1s evaluar el potencial de reducci\u00f3n en el uso de fertilizantes nitrogenados mediante la optimizaci\u00f3n de su aplicaci\u00f3n, sin comprometer la productividad. Se espera que los resultados de esta investigaci\u00f3n contribuyan al desarrollo de estrategias m\u00e1s sostenibles, resilientes y eficientes para la producci\u00f3n de ma\u00edz en la regi\u00f3n O\u0092Higgins y m\u00e1s all\u00e1.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 749253<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de las Culturas, las Artes y el Patrimonio<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26067\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Foro Literario 2025: LIJ en di\u00e1logo \/ Encuentros con la literatura para infancia, adolescencia y juventud.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26067\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26067\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Formaci\u00f3n de mediadores[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ID25I10198<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26604\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Herramientas de machine learning y optimizaci\u00f3n para mejora de calidad de soluciones de ruteo de veh\u00edculos y \u00faltima milla\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26604\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26604\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto pretende desarrollar una herramienta que mejore la calidad de servicio en las rutas entregadas a los distintos clientes de Simpliroute, empresa nacional que entrega servicios de ruteo y recomendaciones de log\u00edstica de \u00faltima milla. Este desarrollo es en dos principales \u00e1mbitos. Primero, poder mejorar la capacidad de rutear a todos los clientes requeridos, detectando y anticipando con IA las ocasiones en donde el algoritmo de ruteo actual no encuentra una soluci\u00f3n factible. El objetivo es detectar anticipadamente estos problemas de infactibilidad y proponer alternativas para entregar una mejor soluci\u00f3n de ruteo. Segundo, usar la informaci\u00f3n de ajuste de rutas de los veh\u00edculos (detenciones, o&#769;rdenes de visita, entre otros) para \u0093aprender\u0094 de estos cambios usando IA, y mejorar la siguiente ruta a entregar. El prototipo a desarrollar se probar\u00e1 con las instancias de ruteo de diferentes clientes evaluando la calidad de servicio de la ruta y el reparto que realizan en sus operaciones.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>CEDEUS<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27097\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estudio Plan Urbano Habitacional (PUH) Las Vi\u00f1itas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27097\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27097\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]An\u00e1lisis de los efectos e impactos[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26963\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            How much does winning matter? Evaluating the effect of assignment to a preferred school and an exploration of who is hurt most by losing the lottery.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26963\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26963\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Chile is entering its eighth year of using a centralized admission system (SAE) to assign students to PK-12 schools accepting public funding. The SAE involved a significant cultural change in how students are assigned to schools, and this change was accompanied by a lot of criticism as families fretted about how to guarantee an academic future for their children (Carrasco, et al., 2020). There was a lot of public discussion about the risk of \u0093losing\u0094 the lottery. While there were always students who lost out on admission to oversubscribed schools (and sometimes even when the school was not oversubscribed), using the SAE families felt that they lost a certain sense of control. Also, with the SAE, the winners and losers become transparent to the public, while before the SAE it was not possible to track the losers. \r\n\tThere have been many studies examining the effect of SAE on access for low-income students, segregation, and on the opinion of parents participating in the SAE (Carrasco, et al., 2021; Honey & Carrasco, 2023; Hern\u00e1ndez, et al., 2023). However, these studies have primarily focused on the initial implementation of the SAE. Now that the policy has had time to mature, it is important to return to the policy to analyze the medium- and longer-term effects of assignment via SAE. To what extent does it matter if a student is assigned to their preferred school? This project aims to identify for whom it really matters if they win the lottery and for whom, even if they lose, their academic future is not in jeopardy. The supply of desirable schools is not evenly distributed across the country, and there are students for whom losing the lottery means having to travel expansive distances in order to reach another desirable school, while there are other students for whom there are multiple attractive options within a reasonable proximity.\r\nThe objective of the project is to better understand the differential effect of winning or losing in the school admission system where desirable schools are unevenly distributed geographically. The research questions are the following: 1)To what extent does assignment to a preferred school through SAE affect a student's sense of belonging in a school, academic aspirations, academic performance, mobility, and entrance into higher education? 2) To what extent is the effect of assignment to a preferred school through SAE moderated by the characteristics of the desirable supply of schools surrounding the student? 3) To what extent are there differential effects of assignment to a preferred school based on gender, family income, indigeneity, nationality, and previous academic achievement? 4) How is a student's perceived college readiness related to their assignment to their first-choice school?\r\nThis project uses a mixture of quantitative and qualitative methods. First, this study involves the categorization of the revealed desirability of schools across neighborhoods. GIS will be used to map the revealed desirability of schools (measured by the applicant-to-vacancy ratio) across neighborhoods. Neighborhoods will be classified by the concentration of high, medium, and low revealed desirability of the schools relative to the number of students residing in the neighborhood. Second, this study involves the analysis of secondary data to conduct a quasi-causal analysis of the effects of assignment by SAE taking full advantage of the deferred acceptance design of SAE. There has been a significant improvement in the methods of analysis of the effect of assignment in these systems by using the deferred acceptance propensity score, which allows researchers to analyze the effect of assignment not only on schools with high oversubscription but also those with modest or even no oversubscription. Finally, this study implements semi-structured interviews to acquire a rich understanding of students' experiences in their schools and their preparation for higher education. Interviews will be conducted with 30 higher education students attending five different types of higher education institutions, allowing for a more thorough understanding of how they perceive that their assignment to (or not to) their preferred high school influenced their ability to get into their desired higher education opportunity and their level of preparation for the institution they are attending.\r\n\tThe anticipated results of this study include the mapping of the supply and demand for schools in a way that takes advantage of the data from SAE to understand not only the distribution of public and private schools but also the real distribution of schools as characterized by their revealed desirability. This will allow policymakers to identify neighborhoods most needing the creation of more desirable school seats. Secondly, this study will allow for the identification of the effects of assignment to a desired school. Preliminary analyses suggest that, on average, the effect of assignment will be minimal; however, in the moderation analyses, it is likely that there will be certain characteristics of students and neighborhoods where winning the lottery is indeed important in shaping one's future. Finally, given the psychology of winning in school choice (Rhinesmith, 2017), it is likely that interviews will reveal that students assigned to their preferred school will attribute more of their post-collegiate success to their secondary school, while those who were not assigned to their preferred secondary school will attribute their success to their own effort. The analyses will be critical as the country considers adapting the rules of SAE to best meet the needs of students who are not granted access to their first-choice school.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> INGE230013<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27056\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Revelando los mecanismos de la respuesta inmune: impacto de Tenacibaculum dicentrarchi en el metiloma del salm\u00f3n del Atl\u00e1ntico.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27056\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27056\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La salmonicultura es una de las principales actividades econ\u00f3micas de Chile por valor exportado, solo superada por el cobre y seguida por las cerezas. En 2023, la producci\u00f3n super\u00f3 el mill\u00f3n de toneladas, alcanzando un valor de 6.463 millones de d\u00f3lares. A pesar de su crecimiento sostenido, la industria enfrenta importantes desaf\u00edos sanitarios, entre ellos, los brotes infecciosos que generan altas p\u00e9rdidas econ\u00f3micas debido a las mortalidades y costos relacionados con el tratamiento. En este contexto, la Tenacibaculosis ha emergido como una enfermedad de alto riesgo, causada por Tenacibaculum dicentrarchi. Desde 2020, es el segundo pat\u00f3geno m\u00e1s letal en salm\u00f3n del Atl\u00e1ntico (Salmo salar), la principal especie cultivada en Chile, despu\u00e9s de Piscirickettsia salmonis causante del S\u00edndrome rickettsial del salm\u00f3n. A pesar de su relevancia, existe escasa informaci\u00f3n sobre la respuesta inmune del salm\u00f3n frente a este pat\u00f3geno, y actualmente no existen vacunas, por lo que se recurre al uso intensivo de antibi\u00f3ticos. Comprender el funcionamiento del sistema inmune frente a T. dicentrarchi es esencial para evaluar el estado sanitario de los peces y dise\u00f1ar tratamientos efectivos. Un aspecto clave de esta comprensi\u00f3n es el impacto potencial del pat\u00f3geno sobre la regulaci\u00f3n inmune a trav\u00e9s de la metilaci\u00f3n del ADN gen\u00f3mico. Se ha demostrado que algunas bacterias pueden alterar estos patrones epigen\u00e9ticos en su beneficio. Este proyecto propone caracterizar la respuesta inmune del salm\u00f3n del Atl\u00e1ntico frente a una infecci\u00f3n por T. dicentrarchi y analizar los cambios inducidos en la metilaci\u00f3n del ADN. Hipotetizamos que la infecci\u00f3n cr\u00f3nica de T. dicentrarchi desencadena cambios en el patr\u00f3n de metilaci\u00f3n del ADN de salm\u00f3n del Atl\u00e1ntico favoreciendo la tolerancia a la infecci\u00f3n. El objetivo general del presente proyecto es demostrar que la infecci\u00f3n cr\u00f3nica por T. dicentrarchi causa cambios en el patr\u00f3n de metilaci\u00f3n del ADN gen\u00f3mico de salm\u00f3n del Atl\u00e1ntico favoreciendo la tolerancia a la infecci\u00f3n a trav\u00e9s de la inmunosupresi\u00f3n de la respuesta inmune. Para demostrar esta hip\u00f3tesis proponemos tres objetivos espec\u00edficos. El primer objetivo espec\u00edfico es \u0093Caracterizar la respuesta inmune de salm\u00f3n del Atl\u00e1ntico (Salmo salar) frente a T. dicentrarchi en condiciones de laboratorio\u0094. Para este objetivo estamos realizando actualmente un desaf\u00edo en salm\u00f3n del Atl\u00e1ntico con T. dicentrarchi donde tomaremos las muestras a analizar para estos objetivos propuestos. El an\u00e1lisis de la respuesta inmune se realizar\u00e1 en diferentes tejidos a trav\u00e9s de RT-PCR. Luego el segundo objetivo espec\u00edfico es \u0093Analizar los cambios en los patrones de metilaci\u00f3n del ADN inducidos por una infecci\u00f3n de T. dicentrarchi en salm\u00f3n del Atl\u00e1ntico\u0094. Para lograr este objetivo nosotras realizaremos una secuenciaci\u00f3n con tecnolog\u00eda Nanopore disponible en la Universidad de O'Higgins, este an\u00e1lisis se realizar\u00e1 con peces controles y peces infectados. El \u00faltimo objetivo espec\u00edfico es \u0093Correlacionar los cambios en los patrones de metilaci\u00f3n del ADN con la respuesta inmune del salm\u00f3n del Atl\u00e1ntico frente a T. dicentrarchi\u0094. Los resultados esperados son: 1) La caracterizaci\u00f3n de la respuesta inmune de los peces infectados y controles a trav\u00e9s de RT-PCR; 2) Verificaci\u00f3n de que T. dicentrarchi desencadena una respuesta inmunitaria del tipo 2 (Th2\/M2); 3) Caracterizaci\u00f3n del cambio de patrones de metilaci\u00f3n en el ADN gen\u00f3mico a causa de la infecci\u00f3n de T. dicentrarchi; 4) Vincular funcionalmente los cambios epigen\u00e9ticos con los efectos inmunol\u00f3gicos observados, esto permitir\u00e1 describir genes potencialmente silenciados que podr\u00edan estar implicados en la tolerancia a esta enfermedad y a ser susceptibles frente a otras infecciones. Los resultados obtenidos en esta investigaci\u00f3n aportar\u00e1n informaci\u00f3n sobre la salud de los animales y el proceso de desarrollo de la enfermedad que contribuir\u00e1n al conocimiento del estado sanitario del salm\u00f3n del Atl\u00e1ntico en el contexto de enfermedades bacterianas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2025 - Marzo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26632\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia y validaci\u00f3n de portainjertos de cucurbit\u00e1ceas resilientes al cambio clim\u00e1tico para el fortalecimiento de la Agricultura Familiar Campesina de la provincia de Cardenal Caro de la regi\u00f3n de O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26632\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26632\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La Agricultura Familiar Campesina (AFC) de la Provincia de Cardenal Caro presenta desaf\u00edos vinculados a la gesti\u00f3n h\u00eddrica y la modernizaci\u00f3n de sus cadenas productivas; que conlleva a una disminuci\u00f3n de rendimientos, aumento de costos productivos y una creciente vulnerabilidad clim\u00e1tica que limitan su potencial de desarrollo. Lo anterior se ha visto acentuado, adem\u00e1s, por el anuncio de al menos 4 decretos de escasez h\u00eddrica (entre 2019 y 2023) por parte del Gobierno de Chile, que abarcan total o parcialmente la regi\u00f3n de O\u0092Higgins, siendo la Provincia de Cardenal Caro una de las m\u00e1s afectadas. Por otro lado, la regi\u00f3n de O'Higgins destaca por su alto Producto Interno Bruto silvoagropecuario, representando el 16,1%; destacando las actividades de producci\u00f3n de cultivos y frutales, siendo la sand\u00eda la tercera hortaliza m\u00e1s producida en la regi\u00f3n con 1.369 ha cultivadas, lo que representa el 46,6% de la producci\u00f3n nacional. En O\u0092Higgins, el cultivo de sand\u00eda se produce principalmente en la provincia de Cachapoal, espec\u00edficamente en las localidades de Quinta de Tilcoco, Pichidegua, Rengo, Las Cabras y Malloa, sin embargo, mediante el desarrollo de nuevas variedades vegetales y a trav\u00e9s del uso de portainjertos, es posible cultivar sand\u00eda en las condiciones edafoclim\u00e1ticas de la provincia de Cardenal Caro, transformando su cultivo en una oportunidad para diversificar la matriz productiva de esta provincia. En este sentido, el cultivo de cucurbit\u00e1ceas, se ha demostrado que presenta buenos m\u00e1rgenes de comercializaci\u00f3n en las localidades de Navidad, Litueche y La Estrella, identific\u00e1ndose una oportunidad para aumentar los rendimientos y n\u00famero de hect\u00e1reas cultivables. En esta propuesta se presenta como soluci\u00f3n cient\u00edfica-tecnol\u00f3gica el desarrollo de un paquete tecnol\u00f3gico, que mediante la validaci\u00f3n y uso de portainjertos de cucurbit\u00e1ceas resilientes al cambio clim\u00e1tico, fortalezca a la AFC de la provincia de Cardenal Caro de la regi\u00f3n de O'Higgins.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26058\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Efecto del perfil proteico (&#946;-case\u00edna A1\/A2) y aminoac\u00eddico de la leche sobre la supervivencia de pat\u00f3genos durante el almacenamiento y su relaci\u00f3n con la percepci\u00f3n de inocuidad y calidad alimentaria de la leche en consumidores\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26058\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26058\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La leche bovina es un alimento fundamental en la nutrici\u00f3n humana, no solo por su aporte de nutrientes esenciales sino tambi\u00e9n por sus propiedades funcionales. En este contexto, la composici\u00f3n proteica, en especial la presencia de las variantes de &#946;-case\u00edna A1 y A2, ha generado creciente inter\u00e9s debido a su influencia en la liberaci\u00f3n de p\u00e9ptidos bioactivos con potencial impacto en la salud gastrointestinal, neurol\u00f3gica y metab\u00f3lica. Entre estos p\u00e9ptidos bioactivos destaca la &#946;-casomorfina-7 (BCM-7) liberada en presencia &#946;-case\u00edna A1. Si bien en estudios internacionales se ha caracterizado la distribuci\u00f3n de las variantes de la &#946;-case\u00edna A1 y A2 en leche comercial, en Chile se requiere profundizar en esta tem\u00e1tica. Sumado a esto, la composici\u00f3n aminoac\u00eddica de la leche influye tanto en su valor nutricional como en sus propiedades antimicrobianas naturales, afectando la supervivencia de bacterias pat\u00f3genas durante el almacenamiento. A nivel de consumidores, aunque el conocimiento sobre las diferencias entre las variantes A1 y A2 de la &#946;-case\u00edna es limitado, existe un creciente inter\u00e9s por productos percibidos como m\u00e1s saludables. Esto evidencia el problema a abordar, que corresponde a la falta de informaci\u00f3n sobre c\u00f3mo el perfil proteico (particularmente las variantes de &#946;-case\u00edna A1 y A2) y la composici\u00f3n aminoac\u00eddica de la leche influyen en la supervivencia de pat\u00f3genos durante su almacenamiento, y c\u00f3mo esto se relaciona con la percepci\u00f3n de calidad e inocuidad por parte de los consumidores chilenos. \r\nLa hip\u00f3tesis del proyecto es que el perfil proteico y aminoac\u00eddico de la leche afecta su calidad e inocuidad, incidiendo en la supervivencia de pat\u00f3genos y en la percepci\u00f3n del consumidor.\r\nPara alcanzar los objetivos, se propone la:\r\n&#61623;Caracterizaci\u00f3n proteica y aminoac\u00eddica de la leche, a trav\u00e9s del an\u00e1lisis de muestras de leche de distintas marcas y tipos disponibles en el mercado nacional.\r\n&#61623;Realizaci\u00f3n de una encuesta a consumidores para evaluar el conocimiento y percepci\u00f3n sobre la calidad e inocuidad de la leche y las variables que las determinan.\r\n&#61623;Ensayos microbiol\u00f3gicos de evaluaci\u00f3n de la supervivencia bacteriana en leche mediante recuento de unidades formadoras de colonias (UFC\/mL) de aerobios mes\u00f3filos y los pat\u00f3genos E.coli y Listeria monocytogenes.\r\nEl proyecto se desarrollar\u00e1 en un per\u00edodo de 15 meses, permitiendo en desarrollo de tres tesis e idealmente dos publicaciones cient\u00edficas, lo que fortalecer\u00e1 la trayectoria acad\u00e9mica de la directora y directora alterna.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26109\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            La lengua, las aulas, las calles: El paisaje ling\u00fc\u00edstico para una did\u00e1ctica de la lengua con pertinencia local\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26109\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26109\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En el quehacer docente, uno de los desaf\u00edos m\u00e1s demandantes que deben enfrentar profesoras y profesores es la necesidad de aplicar innovaci\u00f3n de manera constante en sus metodolog\u00edas de ense\u00f1anza y aprendizaje en las aulas, con el prop\u00f3sito mayor de crear experiencias formativas motivantes, efectivas y significativas. Para ello, adem\u00e1s de generar un ambiente educativo atractivo, se espera que estos m\u00e9todos promuevan el desarrollo de trabajo colaborativo\/interactivo, se vinculen con las din\u00e1micas culturales y sociohist\u00f3ricas propias de las comunidades en que se inserta el quehacer docente y las vidas de estudiantes, tomando en cuenta la realidad del territorio, pero sin perder de vista los fen\u00f3menos de alcance global.\r\nLa presente propuesta tiene como objetivo contribuir a la diversificaci\u00f3n de estrategias did\u00e1ctico-metodol\u00f3gicas de profesoras y profesores del secano costero de la Regi\u00f3n de O\u0092Higgins, a trav\u00e9s de: (a) la implementaci\u00f3n de un taller de varias sesiones, enfocado en el uso del espacio p\u00fablico como herramienta formativa en cursos de lenguaje y (b) la edici\u00f3n de un manual que recoger\u00e1 esta experiencia para su potencial utilizaci\u00f3n futura. Para ello, movilizamos el concepto Paisaje Ling\u00fc\u00edstico (PL); esto es, la materializaci\u00f3n de las lenguas en el espacio p\u00fablico, a trav\u00e9s de los registros escritos que ah\u00ed encontramos. Se trata de un recurso did\u00e1ctico potente, de plena vigencia\/actualidad y que posibilita desarrollar procesos formativos significativos y con pertinencia territorial.\r\nLa implementaci\u00f3n se har\u00e1 en distintas etapas a lo largo de 8 meses de trabajo y contempla: (a) reuniones peri\u00f3dicas del equipo de trabajo durante las diferentes fases del proyecto; (b) encuentros presenciales en modalidad taller para docentes de cursos de lenguaje u otras asignaturas afines; (c) trabajo en grupos de docentes, en terreno, para crear un registro fotogr\u00e1fico del paisaje ling\u00fc\u00edstico del centro de Pichilemu; (d) trabajo de an\u00e1lisis cr\u00edtico guiado, con el objetivo de descubrir qu\u00e9 nos dice respecto de la realidad sociohist\u00f3rica de la comunidad y explorar el modo en que hacemos dialogar aquello con los contenidos propios de las asignaturas y niveles educativos que tienen a cargo; (d) preparaci\u00f3n y realizaci\u00f3n de una jornada de presentaci\u00f3n de resultados en modalidad de muestra fotogr\u00e1fica; y finalmente (e) la edici\u00f3n y publicaci\u00f3n de un manual que recoja los resultados de esta experiencia y que, sobre la base de ella misma, contenga lineamientos e ideas para la implementaci\u00f3n de la metodolog\u00eda del Paisaje Ling\u00fc\u00edstico en futuras iniciativas lideradas por profesoras y profesores.\r\nSe espera que al finalizar el proyecto las y los docentes cuenten con una serie de herramientas te\u00f3rico-metodol\u00f3gicas y un manual que les permita integrar la metodolog\u00eda del Paisaje Ling\u00fc\u00edstico en sus pr\u00e1cticas docentes para la promoci\u00f3n de una educaci\u00f3n ling\u00fc\u00edstica que promueva el trabajo colaborativo, el pensamiento cr\u00edtico, la reflexi\u00f3n metaling\u00fc\u00edstica, junto con valorar la diversidad ling\u00fc\u00edstico-cultural de su territorio en tanto expresi\u00f3n de identidades personales y sociales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26316\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Efecto del perfil proteico (&#946;-case\u00edna A1\/A2) y aminoac\u00eddico de la leche sobre la supervivencia de pat\u00f3genos durante el almacenamiento y su relaci\u00f3n con la percepci\u00f3n de inocuidad y calidad alimentaria de la leche en consumidores\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26316\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26316\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La leche bovina es un alimento fundamental en la nutrici\u00f3n humana, no solo por su aporte de nutrientes esenciales sino tambi\u00e9n por sus propiedades funcionales. En este contexto, la composici\u00f3n proteica, en especial la presencia de las variantes de &#946;-case\u00edna A1 y A2, ha generado creciente inter\u00e9s debido a su influencia en la liberaci\u00f3n de p\u00e9ptidos bioactivos con potencial impacto en la salud gastrointestinal, neurol\u00f3gica y metab\u00f3lica. Entre estos p\u00e9ptidos bioactivos destaca la &#946;-casomorfina-7 (BCM-7) liberada en presencia &#946;-case\u00edna A1. Si bien en estudios internacionales se ha caracterizado la distribuci\u00f3n de las variantes de la &#946;-case\u00edna A1 y A2 en leche comercial, en Chile se requiere profundizar en esta tem\u00e1tica. Sumado a esto, la composici\u00f3n aminoac\u00eddica de la leche influye tanto en su valor nutricional como en sus propiedades antimicrobianas naturales, afectando la supervivencia de bacterias pat\u00f3genas durante el almacenamiento. A nivel de consumidores, aunque el conocimiento sobre las diferencias entre las variantes A1 y A2 de la &#946;-case\u00edna es limitado, existe un creciente inter\u00e9s por productos percibidos como m\u00e1s saludables. Esto evidencia el problema a abordar, que corresponde a la falta de informaci\u00f3n sobre c\u00f3mo el perfil proteico (particularmente las variantes de &#946;-case\u00edna A1 y A2) y la composici\u00f3n aminoac\u00eddica de la leche influyen en la supervivencia de pat\u00f3genos durante su almacenamiento, y c\u00f3mo esto se relaciona con la percepci\u00f3n de calidad e inocuidad por parte de los consumidores chilenos. \r\nLa hip\u00f3tesis del proyecto es que el perfil proteico y aminoac\u00eddico de la leche afecta su calidad e inocuidad, incidiendo en la supervivencia de pat\u00f3genos y en la percepci\u00f3n del consumidor.\r\nPara alcanzar los objetivos, se propone la:\r\n&#61623;Caracterizaci\u00f3n proteica y aminoac\u00eddica de la leche, a trav\u00e9s del an\u00e1lisis de muestras de leche de distintas marcas y tipos disponibles en el mercado nacional.\r\n&#61623;Realizaci\u00f3n de una encuesta a consumidores para evaluar el conocimiento y percepci\u00f3n sobre la calidad e inocuidad de la leche y las variables que las determinan.\r\n&#61623;Ensayos microbiol\u00f3gicos de evaluaci\u00f3n de la supervivencia bacteriana en leche mediante recuento de unidades formadoras de colonias (UFC\/mL) de aerobios mes\u00f3filos y los pat\u00f3genos E.coli y Listeria monocytogenes.\r\nEl proyecto se desarrollar\u00e1 en un per\u00edodo de 15 meses, permitiendo en desarrollo de tres tesis e idealmente dos publicaciones cient\u00edficas, lo que fortalecer\u00e1 la trayectoria acad\u00e9mica de la directora y directora alterna.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2025 - Febrero 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26358\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Agregaci\u00f3n de valor a productos de la AFC del seco costero de la regi\u00f3n de O&#8217;Higgins, mediante tecnolog\u00eda de liofilizaci\u00f3n en la elaboraci\u00f3n de producto y del packaging para comercializaci\u00f3n\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26358\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26358\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La Agricultura Familiar Campesina (AFC) y la microempresa agroalimentaria de la regi\u00f3n de O\u0092Higgins enfrentan m\u00faltiples desaf\u00edos a lo largo de su cadena de valor, particularmente en lo que respecta a la agregaci\u00f3n de valor, comercializaci\u00f3n y acceso a tecnolog\u00edas. La falta de infraestructura, conocimientos y capacidades t\u00e9cnicas limita la transformaci\u00f3n de materias primas en productos diferenciados y rentables, afectando directamente la sustentabilidad econ\u00f3mica de estos actores.\r\nEn este contexto, la provincia de Cardenal Caro presenta una situaci\u00f3n a\u00fan m\u00e1s compleja. Cinco de sus seis comunas \u0097La Estrella, Litueche, Navidad, Paredones y Pichilemu\u0097 han sido catalogadas como territorios de rezago por el Gobierno Regional de O\u0092Higgins, debido a su aislamiento geogr\u00e1fico, limitadas redes de conectividad vial y digital, y una baja densidad empresarial (7% de las empresas regionales seg\u00fan SII, 2018). Estas condiciones afectan negativamente el desarrollo productivo, la inclusi\u00f3n tecnol\u00f3gica y la calidad de vida de su poblaci\u00f3n.\r\nSi bien se han logrado avances a trav\u00e9s de iniciativas colaborativas entre academia e instituciones p\u00fablicas, persisten importantes brechas tecnol\u00f3gicas. Una de ellas es el uso de m\u00e9todos tradicionales de deshidrataci\u00f3n de productos como algas, hierbas medicinales o productos ap\u00edcolas. El secado por convecci\u00f3n (natural o forzada) suele provocar p\u00e9rdidas significativas en atributos sensoriales y funcionales (sabor, aroma, polifenoles, capacidad antioxidante), limitando su competitividad.\r\nEl presente proyecto propone incorporar la liofilizaci\u00f3n como tecnolog\u00eda de deshidrataci\u00f3n innovadora, que mediante la sublimaci\u00f3n del agua permite preservar las cualidades nutricionales y sensoriales de los productos. Junto a ello, se considera esencial el dise\u00f1o del packaging, abordando tanto la materialidad como la estrategia gr\u00e1fica, con el fin de asegurar la conservaci\u00f3n post-liofilizaci\u00f3n y mejorar el posicionamiento comercial del producto final.\r\nA trav\u00e9s de una metodolog\u00eda basada en talleres, validaciones de proceso y actividades de transferencia, se busca mejorar las capacidades t\u00e9cnicas de peque\u00f1os productores de la provincia, generar productos con mayor valor agregado y fortalecer la inserci\u00f3n de la AFC del secano costero en circuitos de comercializaci\u00f3n diferenciada.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 19591<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2025 - Octubre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26693\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Explorando la coocurrencia entre autismo y diversidad de g\u00e9nero: intersecciones, identidades y transiciones en la adolescencia y la adultez joven.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26693\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26693\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Si bien, hay algunos estudios que sugieren un v\u00ednculo entre la diversidad de G\u00e9nero (DiG) y las personas autistas, esta relaci\u00f3n est\u00e1 poco explorada, especialmente en Latinoam\u00e9rica, existiendo muchas limitaciones en las instrumentos y metodolog\u00edas utilizados en los diferentes estudios. En ese sentido, el proyecto busca explorar la relaci\u00f3n entre los rasgos autistas y diversidad de g\u00e9nero en adolescentes j\u00f3venes entre 13 a 21 a\u00f1os, que consultan en centros de salud p\u00fablica y privada en Chile en diversas regiones de Chile de la zona Norte (ejemplo Iquique), Centro (ejemplo Metropolitana y de O\u0092Higgins) y Sur (Los Lagos). Para esto, se implementar\u00e1 un estudio transversal, descriptivo y exploratorio con enfoque mixto (cuantitativo y cualitativo).[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 19591<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2025 - Octubre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26845\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Explorando la coocurrencia entre autismo y diversidad de g\u00e9nero: intersecciones, identidades y transiciones en la adolescencia y la adultez joven.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26845\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26845\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Si bien, hay algunos estudios que sugieren un v\u00ednculo entre la diversidad de G\u00e9nero (DiG) y las personas autistas, esta relaci\u00f3n est\u00e1 poco explorada, especialmente en Latinoam\u00e9rica, existiendo muchas limitaciones en las instrumentos y metodolog\u00edas utilizados en los diferentes estudios. En ese sentido, el proyecto busca explorar la relaci\u00f3n entre los rasgos autistas y diversidad de g\u00e9nero en adolescentes j\u00f3venes entre 13 a 21 a\u00f1os, que consultan en centros de salud p\u00fablica y privada en Chile en diversas regiones de Chile de la zona Norte (ejemplo Iquique), Centro (ejemplo Metropolitana y de O\u0092Higgins) y Sur (Los Lagos). Para esto, se implementar\u00e1 un estudio transversal, descriptivo y exploratorio con enfoque mixto (cuantitativo y cualitativo).[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26996\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Violencias, pr\u00e1cticas familiares de securitizaci\u00f3n y producci\u00f3n del orden social en asentamientos informales de la Regi\u00f3n de O\u0092Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26996\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26996\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto se enfoca en comprender c\u00f3mo las pr\u00e1cticas cotidianas de securizaci\u00f3n\r\ndesarrolladas por los habitantes de asentamientos informales en la regi\u00f3n de O\u0092Higgins (Chile) configuran\r\ntanto el orden social como el espacio urbano. La pregunta central del estudio es: \u00bfc\u00f3mo las comunidades\r\nque habitan campamentos producen y transforman su entorno urbano y social a trav\u00e9s de pr\u00e1cticas\r\ncotidianas relativas a la seguridad?[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27090\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Violencias, pr\u00e1cticas familiares de securitizaci\u00f3n y producci\u00f3n del orden social en asentamientos informales de la Regi\u00f3n de O\u0092Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27090\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27090\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto se enfoca en comprender c\u00f3mo las pr\u00e1cticas cotidianas de securizaci\u00f3n\r\ndesarrolladas por los habitantes de asentamientos informales en la regi\u00f3n de O\u0092Higgins (Chile) configuran\r\ntanto el orden social como el espacio urbano. La pregunta central del estudio es: \u00bfc\u00f3mo las comunidades\r\nque habitan campamentos producen y transforman su entorno urbano y social a trav\u00e9s de pr\u00e1cticas\r\ncotidianas relativas a la seguridad?[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2025 - Abril 2028<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26565\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Qualitative behaviour of nonlinear PDE from Physics and Biology\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26565\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26565\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]This research proposal aims to study the long-term behavior of solutions to partial differential equations arising from dispersive dynamics, kinetic models, and integro-differential dynamics in ecology; and to study extremals of functional inequalities in connection to the ground states of partial differential equations arising from quantum mechanics and diffusion phenomena. Five major topics are proposed: Relativistic quantum mechanics, Dirac operators and functional inequalities; Symmetry breaking in weighted functional inequalities and weighted diffusions; long time dynamics in dispersive PDEs in one space dimension; long-term dynamics in nonlocal models from ecology; and hypocoercivity and decay to equilibrium in kinetic models with heavy tails.\r\n\r\nThe first topic focuses on establishing connections between spectral problems and functional inequalities for Dirac operators. The aim is to analyse the symmetry of optimal spinors in inequalities of Keller-Lieb-Thirring type, and to obtain the solitary waves of Soler-type nonlinear Dirac equations as optimizers of a nonlinear inequality. The second topic aims to characterize a symmetry range in which optimal functions are radially symmetric for weighted logarithmic Sobolev inequalities and a new family of Caffarelli-Kohn-Nirenberg inequalities. A nonlinear carr\u00e9-du-champ method will be adapted to prove entropy-type estimates. Rigidity, perturbation, and stability issues will be addressed. The third topic seeks to study the asymptotic stability of topological and non-topological solitions for a class of dispersive PDEs in dimension one. A new method is proposed, based on perturbations in weighted spaces with exponential weights, on the so-called virial identities, and on the study of existence of breathers. The fourth topic concerns the description of evolutionary stable strategies of long-term dynamics of integro-differential models that arise in the modeling of structured populations, and to obtain qualitative and quantitative insights on the concentration dynamics. In the fifth topic, the aim is to extend the Dolbeault-Mouhot-Schmeiser method to study the large-time behavior of solutions for a broad family of kinetic equations in which the confinement potential exhibits heavy tails.\r\n\r\nThe goals of this project are multiple: to strengthen and to create new collaborative research networks between France and Chile in the field of nonlinear partial differential equations and applications, to publish co-authored articles in top-tier journals and disseminate the results in international meetings, and to promote the formation of advanced human capital. In order to achieve these goals, yearly workshops will be organized in France and Chile to account for the progress of the investigations as well as to encourage the participation of students and young researchers. International training of doctoral and postdoctoral researchers will be ensured by allocating resources from this project for exchanges. Considering the history of successful collaboration amongst the members of this project, and their expertise in their research fields, we are confident about the successful termination of the project. In particular, we expect to pave the way for new research avenues.\r\n\r\nThe main scientific contribution of this proposal involves adapting state-of-the-art techniques from PDEs and nonlinear analysis to obtain qualitative and quantitative results for variational problems and partial differential equations, in which the setting plays a crucial role: complex-valued matrices (first topic), nonlinear and weighted (second topic), strongly nonlinear and dispersive (third topic), nonlocal (fourth topic), general assumption on the tail of the confining potential (fifth topic). This proposed research will provide insights into spectral theory, stability theory of equilibria of differential equations, optimal rates of convergence to equilibria, and their relation to optimal constants in functional inequalities. The expected results will help improving the understanding of various real-life phenomena, including population-dynamics, relativistic quantum mechanics, and diffussion processes. The viability of the project is sustained on the expertise of the members of the Chilean and French research teams, including experts in partial differential equations, nonlinear analysis, calculus of variations, and mathematical physics. Their successful collaboration record and significant contributions to these fields only strengthen the potential of this proposal.\r\n\r\nIn conclusion, the present research project will not only foster the scientific cooperation between Chile and France but it will also provide meaningful advancements in the aforementioned fields and their application to various physical phenomena.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1251095<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2025 - Marzo 2028<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26189\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Imprints of multiple global change drivers on biodiversity and ecosystem functioning within and across bioregions\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26189\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26189\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto analiza c\u00f3mo distintos impulsores del cambio global afectan la biodiversidad y el funcionamiento de los ecosistemas en Chile, considerando su ocurrencia simult\u00e1nea y su interacci\u00f3n a lo largo de gradientes ambientales y antr\u00f3picos. Mediante un enfoque de macrosistemas, se busca comprender c\u00f3mo estos factores pueden modificar patrones de diversidad, estructura de comunidades y procesos ecosist\u00e9micos, incluyendo fen\u00f3menos como la homogeneizaci\u00f3n bi\u00f3tica. La investigaci\u00f3n combina an\u00e1lisis biogeogr\u00e1ficos, dise\u00f1os de muestreo multiescala, modelaci\u00f3n ecol\u00f3gica y evaluaci\u00f3n de funciones ecosist\u00e9micas asociadas al ciclo de nutrientes, hidrolog\u00eda y producci\u00f3n de biomasa vegetal. Los resultados permitir\u00e1n entender mejor las consecuencias del cambio global sobre la biodiversidad y los servicios ecosist\u00e9micos, aportando bases cient\u00edficas para la conservaci\u00f3n y gesti\u00f3n sostenible de los ecosistemas frente a escenarios de cambio ambiental.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1251064<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2025 - Enero 2028<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26186\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Soil microbial community structure and carbon and nitrogen functionality responses to combined effects of drought and fires in Mediterranean forest ecosystems\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26186\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26186\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Climate projections anticipate an increase in frequent droughts, episodes of extreme fire behavior, in addition to heat waves and unstable atmospheric conditions, all phenomena related to climate change. Drought intensification has been projected to increase in frequency in several regions across the globe, including the southwestern part of South America, the European Mediterranean Basin, Northern Africa, the Middle East, Central Asia, Australia, and the USA. Particularly, the former three areas have been recognized as locations highly likely to face unprecedented droughts during the 21st century, and within Southwestern South America, Chile has been alarmingly pointed out as the country earlier in this era experiencing this phenomenon, regardless of the greenhouse gas emissions scenario. Catastrophic effects such as extreme droughts and changes in fire behavior are important drivers of ecosystem degradation in arid, semiarid, dry temperate and Mediterranean ecosystems. Mediterranean ecosystems of central Chile have been indicated as the earliest in its type experiencing effects of climate change; where an accelerated aridification is already registered; therefore, representing a scenario to anticipate the effects of climate anomalies at other ecosystems of its type. Persistent droughts and land burning can compromise belowground conditions that are essential to support aboveground life in terrestrial ecosystems. Nevertheless, despite their importance for ecosystem functioning and recovery after environmental disturbances, there still a considerable lack of comprehension on how belowground attributes respond to combined stressors such as droughts and fires. This is of particular concern in conditions where post-fire plant and soil recovery have been shown to be inhibited or retarded due to severe droughts. Therefore, this project aims to evaluate individual and combined effects of drought and fires over time in soil microbial communities and carbon and nitrogen functional dynamics along with the relationship of these attributes and the state of sclerophyll vegetation in Mediterranean forests of central Chile. To accomplish this goal a multiscale approach will be applied in this research by integrating scientific disciplines from landcape ecology to molecular biology. By using remote sensing study site will be selected within an area known to be affected by an extended drought period (since 2010), in addition to hyper-dry years (2019 and 2021), which in addition has experienced the occurrence of historical wildfires as the case of 2017. From this initial screening \r\n18 study conditions resulting from three climate anomaly categories identified (high, medium, low) according to differences in precipitation with respect to historical average, three categories for forest response to drought (recovered, unaffected and unrecovered) based on analysis of Normalized Burn Index (NBR = [NIR - SWIR] \/ [NIR + SWIR]) and two burned conditions (with and without) will be obtained for soil and vegetation assessments. Classical soil physicochemical analyses and NG-sequencing techniques including high-throughput amplicon sequencing (metabarcoding), whole genome sequencing (metagenomics), and gene expression (metatransciptomics), in addition to soil physiological analyses will be performed. Moreover, vegetation recovery following drought and fire will be evaluated. Results from this study will allow to better understand the individual versus the combined effects of drought and fires in soil microbial community structure and carbon and nitrogen functionality, which are expected to be exacerbated with the combined occurrence of these phenomena, giving insights on the resilience capacity of soil microbiomes and carbon and nitrogen biogeochemical cycles. From this work, results will also allow to gain a more comprehensive understanding of the linkages between soil functionality and vegetation responses to drought and fires over time, which will allow to identify ecological drivers related to ecosystem stability.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1251000<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2025 - Marzo 2028<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26190\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Unraveling the effect of antibiotics and co-contaminants, in soil-solution on transport, degradation and uptake by plants, in soils of contrasting mineralogy and organic matter content\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26190\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26190\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto investiga el impacto de la co-contaminaci\u00f3n por antibi\u00f3ticos veterinarios y metales\/iones inorg\u00e1nicos en suelos, un problema emergente asociado a pr\u00e1cticas agr\u00edcolas intensivas como la aplicaci\u00f3n de esti\u00e9rcol, fertilizaci\u00f3n intensiva y riego con aguas residuales. La investigaci\u00f3n se centra en comprender c\u00f3mo la formaci\u00f3n de complejos antibi\u00f3tico-metal\/i\u00f3n influye en procesos clave como la adsorci\u00f3n, degradaci\u00f3n, transporte en el suelo y absorci\u00f3n por plantas, as\u00ed como en la actividad y estructura de las comunidades microbianas. Para ello, se evaluar\u00e1n distintos tipos de suelos relevantes en sistemas agropecuarios intensivos en Chile, integrando modelaci\u00f3n de transporte de solutos, estudios de especiaci\u00f3n qu\u00edmica, experimentos en columnas de suelo y an\u00e1lisis de absorci\u00f3n vegetal. Los resultados permitir\u00e1n mejorar la comprensi\u00f3n del destino ambiental de estas mezclas complejas de contaminantes y aportar bases cient\u00edficas para el desarrollo de estrategias de manejo, mitigaci\u00f3n y remediaci\u00f3n de suelos afectados.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1251766<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26242\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Learning through auditory stimuli: effect of music previously conditioned with nutritional and non-nutritional rewards on the performance and welfare of nursery pigs.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26242\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26242\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Learning through auditory stimuli: effect of music previously conditioned with nutritional and non-nutritional rewards on the performance and welfare of nursery pigs.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2025 - Marzo 2029<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26270\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Targeting Pattern-Triggered Immunity to Engineer Root Microbiomes for Improved Plant Health\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26270\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26270\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Plants, with their two-layered immune system, are equipped to combat pathogen invasion. The first layer, Pattern Triggered Immunity (PTI), is a powerful defense mechanism. It relies on Pattern Recognition Receptors (PRRs) to detect Microbe-Associated Molecular Patterns (MAMPs) from microbes, triggering a robust defense response. This response, including signaling cascades, gene expression changes, and production of antimicrobials and defense hormones, contributes to restricting pathogen colonization. PTI activation can trigger a systemic response known as Induced Systemic Resistance (IRS), enhancing plant defenses throughout the organism and leading to Non-Host-Resistance. The potential of PTI activation to enhance a plant's overall defensive capacity is a promising strategy to improve crop health.  PTI activation at infection sites triggers the production of mobile signals within the plant, which then spread IRS throughout the plant, enhancing its overall defensive capacity.  Flg22 and xyn11, two well-known MAMPs, trigger PTI in tomato, activating various defense responses and, interestingly, including IRS in tomatoes and other plants.\r\nPlant roots, often overlooked in discussions of plant immune systems, possess their own immune system, though less potent than leaves. They respond to MAMPs like Flg22 and chitin, but with weaker production of defense chemicals. Despite this difference, roots activate various defenses like PR proteins and callose deposition. Uniquely, roots secrete antifungal secondary metabolites like flavonoids. These root exudates play a crucial role in shaping the surrounding microbiome, attracting beneficial microbes, and possess antimicrobial activity itself.  Studies have shown that root exudate composition can be manipulated to influence the soil microbiome and potentially enhance plant growth. This underlines the importance of considering roots in our understanding of plant immune systems, particularly how defense responses are displayed in the root after immune activation in leaves in terms of a systemic immune response. This often overlooked aspect is crucial for a comprehensive understanding of plant immunity.\r\nPlants and microbes communicate two-way, establishing an interaction, by instance, plant root exudates influence the composition of the rhizosphere microbiome, which in turn regulates plant growth and immunity. Research suggests that specific bacteria within the rhizosphere microbiome can enhance plant immunity.  In fact, transplanting the microbiome from a resistant tomato variety to a susceptible one improved disease resistance. Understanding this plant-microbiome-soil interaction is crucial for developing sustainable agriculture.  Our ongoing research investigates how soil type influences tomato immunity and its connection to the soil microbiome.  Preliminary results show that different soil types affect the strength of plant immunity responses, even though the overall bacterial types (phyla) are similar.  Interestingly, specific bacterial isolates from a soil type with higher immunity were able to directly trigger plant defense mechanisms. Unraveling the intricate interplay between soil type, the rhizosphere microbiome, and tomato immunity holds the key to unlocking sustainable and resilient agricultural practices.\r\nThis proposal aims to investigate the potential of targeted Pattern-Triggered Immunity (PTI) activation in tomato leaves to enhance plant defense against diverse pathogens. We hypothesize that leaf application of microbial elicitors (flg22 and Xyn11) will trigger PTI, leading to changes in root gene expression and root exudate composition. These alterations are expected to enrich beneficial bacteria in the rhizosphere microbiome, ultimately enhancing resistance against both the foliar pathogen Pseudomonas syringae pv. tomato and the soil-borne pathogen Fusarium oxysporum f.sp. lycopersici. To achieve this, we have defined three specific objectives: 1) Evaluate the impact of leaf-applied elicitors on pathogen susceptibility, root gene expression, root exudate composition, and soil microbiome composition. 2) Develop synthetic exudates mimicking PTI-activated plants and construct synthetic microbial communities potentially containing beneficial bacteria. 3) Assess the effectiveness of leaf-applied elicitors and synthetic microbial communities on the root microbiome and plant health under field conditions. With this, we aim to elucidate the mechanisms by which leaf-based PTI activation influences root-level processes and shapes the rhizosphere microbiome to enhance tomato plant defense against various pathogens. The findings hold promise for developing novel and sustainable strategies for disease management in tomato production.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2025 - Marzo 2029<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26398\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Targeting Pattern-Triggered Immunity to Engineer Root Microbiomes for Improved Plant Health\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26398\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26398\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Plants, with their two-layered immune system, are equipped to combat pathogen invasion. The first layer, Pattern Triggered Immunity (PTI), is a powerful defense mechanism. It relies on Pattern Recognition Receptors (PRRs) to detect Microbe-Associated Molecular Patterns (MAMPs) from microbes, triggering a robust defense response. This response, including signaling cascades, gene expression changes, and production of antimicrobials and defense hormones, contributes to restricting pathogen colonization. PTI activation can trigger a systemic response known as Induced Systemic Resistance (IRS), enhancing plant defenses throughout the organism and leading to Non-Host-Resistance. The potential of PTI activation to enhance a plant's overall defensive capacity is a promising strategy to improve crop health.  PTI activation at infection sites triggers the production of mobile signals within the plant, which then spread IRS throughout the plant, enhancing its overall defensive capacity.  Flg22 and xyn11, two well-known MAMPs, trigger PTI in tomato, activating various defense responses and, interestingly, including IRS in tomatoes and other plants.\r\nPlant roots, often overlooked in discussions of plant immune systems, possess their own immune system, though less potent than leaves. They respond to MAMPs like Flg22 and chitin, but with weaker production of defense chemicals. Despite this difference, roots activate various defenses like PR proteins and callose deposition. Uniquely, roots secrete antifungal secondary metabolites like flavonoids. These root exudates play a crucial role in shaping the surrounding microbiome, attracting beneficial microbes, and possess antimicrobial activity itself.  Studies have shown that root exudate composition can be manipulated to influence the soil microbiome and potentially enhance plant growth. This underlines the importance of considering roots in our understanding of plant immune systems, particularly how defense responses are displayed in the root after immune activation in leaves in terms of a systemic immune response. This often overlooked aspect is crucial for a comprehensive understanding of plant immunity.\r\nPlants and microbes communicate two-way, establishing an interaction, by instance, plant root exudates influence the composition of the rhizosphere microbiome, which in turn regulates plant growth and immunity. Research suggests that specific bacteria within the rhizosphere microbiome can enhance plant immunity.  In fact, transplanting the microbiome from a resistant tomato variety to a susceptible one improved disease resistance. Understanding this plant-microbiome-soil interaction is crucial for developing sustainable agriculture.  Our ongoing research investigates how soil type influences tomato immunity and its connection to the soil microbiome.  Preliminary results show that different soil types affect the strength of plant immunity responses, even though the overall bacterial types (phyla) are similar.  Interestingly, specific bacterial isolates from a soil type with higher immunity were able to directly trigger plant defense mechanisms. Unraveling the intricate interplay between soil type, the rhizosphere microbiome, and tomato immunity holds the key to unlocking sustainable and resilient agricultural practices.\r\nThis proposal aims to investigate the potential of targeted Pattern-Triggered Immunity (PTI) activation in tomato leaves to enhance plant defense against diverse pathogens. We hypothesize that leaf application of microbial elicitors (flg22 and Xyn11) will trigger PTI, leading to changes in root gene expression and root exudate composition. These alterations are expected to enrich beneficial bacteria in the rhizosphere microbiome, ultimately enhancing resistance against both the foliar pathogen Pseudomonas syringae pv. tomato and the soil-borne pathogen Fusarium oxysporum f.sp. lycopersici. To achieve this, we have defined three specific objectives: 1) Evaluate the impact of leaf-applied elicitors on pathogen susceptibility, root gene expression, root exudate composition, and soil microbiome composition. 2) Develop synthetic exudates mimicking PTI-activated plants and construct synthetic microbial communities potentially containing beneficial bacteria. 3) Assess the effectiveness of leaf-applied elicitors and synthetic microbial communities on the root microbiome and plant health under field conditions. With this, we aim to elucidate the mechanisms by which leaf-based PTI activation influences root-level processes and shapes the rhizosphere microbiome to enhance tomato plant defense against various pathogens. The findings hold promise for developing novel and sustainable strategies for disease management in tomato production.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1251064<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2025 - Enero 2028<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26493\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Soil microbial community structure and carbon and nitrogen functionality responses to combined effects of drought and fires in Mediterranean forest ecosystems\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26493\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26493\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Climate projections anticipate an increase in frequent droughts, episodes of extreme fire behavior, in addition to heat waves and unstable atmospheric conditions, all phenomena related to climate change. Drought intensification has been projected to increase in frequency in several regions across the globe, including the southwestern part of South America, the European Mediterranean Basin, Northern Africa, the Middle East, Central Asia, Australia, and the USA. Particularly, the former three areas have been recognized as locations highly likely to face unprecedented droughts during the 21st century, and within Southwestern South America, Chile has been alarmingly pointed out as the country earlier in this era experiencing this phenomenon, regardless of the greenhouse gas emissions scenario. Catastrophic effects such as extreme droughts and changes in fire behavior are important drivers of ecosystem degradation in arid, semiarid, dry temperate and Mediterranean ecosystems. Mediterranean ecosystems of central Chile have been indicated as the earliest in its type experiencing effects of climate change; where an accelerated aridification is already registered; therefore, representing a scenario to anticipate the effects of climate anomalies at other ecosystems of its type. Persistent droughts and land burning can compromise belowground conditions that are essential to support aboveground life in terrestrial ecosystems. Nevertheless, despite their importance for ecosystem functioning and recovery after environmental disturbances, there still a considerable lack of comprehension on how belowground attributes respond to combined stressors such as droughts and fires. This is of particular concern in conditions where post-fire plant and soil recovery have been shown to be inhibited or retarded due to severe droughts. Therefore, this project aims to evaluate individual and combined effects of drought and fires over time in soil microbial communities and carbon and nitrogen functional dynamics along with the relationship of these attributes and the state of sclerophyll vegetation in Mediterranean forests of central Chile. To accomplish this goal a multiscale approach will be applied in this research by integrating scientific disciplines from landcape ecology to molecular biology. By using remote sensing study site will be selected within an area known to be affected by an extended drought period (since 2010), in addition to hyper-dry years (2019 and 2021), which in addition has experienced the occurrence of historical wildfires as the case of 2017. From this initial screening \r\n18 study conditions resulting from three climate anomaly categories identified (high, medium, low) according to differences in precipitation with respect to historical average, three categories for forest response to drought (recovered, unaffected and unrecovered) based on analysis of Normalized Burn Index (NBR = [NIR - SWIR] \/ [NIR + SWIR]) and two burned conditions (with and without) will be obtained for soil and vegetation assessments. Classical soil physicochemical analyses and NG-sequencing techniques including high-throughput amplicon sequencing (metabarcoding), whole genome sequencing (metagenomics), and gene expression (metatransciptomics), in addition to soil physiological analyses will be performed. Moreover, vegetation recovery following drought and fire will be evaluated. Results from this study will allow to better understand the individual versus the combined effects of drought and fires in soil microbial community structure and carbon and nitrogen functionality, which are expected to be exacerbated with the combined occurrence of these phenomena, giving insights on the resilience capacity of soil microbiomes and carbon and nitrogen biogeochemical cycles. From this work, results will also allow to gain a more comprehensive understanding of the linkages between soil functionality and vegetation responses to drought and fires over time, which will allow to identify ecological drivers related to ecosystem stability.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> Fondecyt Regular N\u00b0 1252205<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2025 - Marzo 2028<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26533\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            T\u00edtulo del Proyecto: \u00bfCree la ciudadan\u00eda en los principios penales liberales que sustentan la justicia penal chileno? Estudio mixto sobre sus factores explicativos y consecuencias pol\u00edtico criminales.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26533\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26533\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Beccaria  y la escuela cl\u00e1sica pusieron en tela de juicio el sistema de justicia medieval caracterizado por su arbitrariedad y excesiva crueldad. De esta forma, propusieron un conjunto de ideas (p.ej. legalidad, humanidad y proporcionalidad de las penas, debido proceso) para limitar el poder de castigo estatal, racionalizar el uso de la fuerza y disminuir la aplicaci\u00f3n de la crueldad, llevando reformar el sistema penal de la \u00e9poca. El pensamiento de otros autores y la emergencia de los derechos humanos permitieron que estas ideas se incorporaran en las actuales democracias liberales comprometidas con el Estado de derecho. As\u00ed, en el \u00e1mbito penal, a nivel de leyes, constitucional y del derecho internacional, se construy\u00f3 un sistema de protecci\u00f3n del individuo frente al ius puniendi, y que aqu\u00ed englobamos ampliamente bajo el t\u00e9rmino \u0093Principios Penales liberales\u0094 (en adelante PPL) para referirnos a aquellos principios, sub-principios, ideas, derechos y\/o garant\u00edas destinadas a limitar y racionalizar el ejercicio de la justicia penal. \r\n\r\nAunque estos PPL se encuentran incorporados e institucionalizados, corrientes actuales como el Populismo Penal , la cultura del Control, la punitividad p\u00fablica, el Derecho Penal del enemigo o los estudios en actitudes punitivas permitir\u00edan pensar que los PPL tendr\u00edan hoy un bajo respaldo ciudadano. Adem\u00e1s, en el actual contexto chileno caracterizado por un incremento en la preocupaci\u00f3n por la seguridad, es esperable que la opini\u00f3n p\u00fablica vea con reticencia estos PPLL por considerarse que favorecen a los delincuentes y limitan la capacidad estatal para controlar el crimen. Desde el \u00e1mbito pol\u00edtico, que descansa en buena medida en la opini\u00f3n p\u00fablica, algunos actores plantean restablecer la pena de muerte, buscan limitar derecho a defensa gratuito o aumentar desproporcionadamente las penas.  Tambi\u00e9n, desde ciertos sectores pol\u00edticos se ha presionado o cuestionado el actuar de jueces\/as y fiscal\u00eda sin evaluar las consecuencias de estas acciones para la imparcialidad, en un contexto en el que el t\u00e9rmino de \u0091garantismo jur\u00eddico\u0092 parece ser concebido como como una caracter\u00edstica negativa del sistema jur\u00eddico. Medidas y acciones de este tipo amenazan este conjunto de PPL y la protecci\u00f3n del individuo frente al Estado.  \r\nDado que, desde el punto de vista politol\u00f3gico, las instituciones requieren de cierto umbral de respaldo subjetivo para su legitimidad social, resulta fundamental estudiar el apoyo ciudadano a los PPL que subyacen al sistema de justicia penal. A pesar, sin embargo, de la relevancia de este tema, la literatura en torno a lo que en adelante llamaremos las \u0091Actitudes Ciudadanas hacia los Principios Penales Liberales\u0092 (en adelante APPL) es sumamente escasa. Investigaciones previas solo han abordado el respaldo hacia ciertos principios aislados, hacia un set de PPL , pero no hacia el conjunto completo de PPL subyacentes  al sistema de justicia. Sin embargoA pesar de lo anterior, investigaci\u00f3n seminal y exploratoria en torno al tema se ha realizado en el contexto chileno identific\u00e1ndose una baja adhesi\u00f3n ciudadana a los PPL y, tambi\u00e9n,a la vez que, esto se han encontradomantendr\u00eda un correlatos con el g\u00e9nero, la educaci\u00f3n y la orientaci\u00f3n pol\u00edtica de las personas. Por \u00faltimoOtro ejemplo de investigaci\u00f3n emergente en la tem\u00e1tica es, en Reino Unido. En este \u00faltimo p\u00e1\u00eds -con sistema jur\u00eddico consuetudinario- se ha validado a nivel confirmatorio una escala (actualmente en revisi\u00f3n) para medir las APPL (en adelante E-APPL). Empero, esta escala no ha sido aplicada aun en otros pa\u00edses, o contextos con sistema de derecho escrito. Adicionalmente, tampoco hay hallazgos sobre los posibles factores explicativos de las APPL y sus consecuencias, relev\u00e1ndose entonces un vac\u00edo de conocimiento necesario de abordar. \r\n\r\nConsiderando esto, y mediante una metodolog\u00eda mixta (cuantitativa y cualitativa), nuestra investigaci\u00f3n busca estudiar las APPL en poblaci\u00f3n residente en Chile. Espec\u00edficamente, se busca a) describir los niveles y tipos APPL, b) los posibles factores que explican o dan cuenta de las APPL, y c) las consecuencias de las APPL para la legitimidad y confianza en el sistema de justicia chileno.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26549\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Media Framing of the Securitization of &quot;Migration Crisis&quot; in Chile: A longitudinal study of the national mainstream press, 2014-2026.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26549\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26549\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The nation-state is an organization defined by two principles: its interests (e.g., political, economic, cultural) and its security. Therefore, states constantly seek survival, in which security plays a prominent role, surpassing all other issues (Waltz, 1979). The extent to which the movement of people across international borders has become a security issue is evident in how the migration-security nexus is prevalent in the current public and media debate around the globe, including Chile. This proposal stands on the premise that in a democratic society, mainstream media press is a highly significant actor in influencing levels of public concern and shaping people's attitudes towards social developments and phenomena, including migration and its securitization (Scherman et al., 2022; Ekman & Krzyzanowski, 2021). The representation of immigrants in mainstream media press creates opportunities for immigrants to either become part of society or be excluded from the public sphere. \r\nThe main objective of this proposal is to analyze the media framing of the securitization of the \"migration crisis\" in the Chilean mainstream media press during 2014-2026. Further on, this main objective is broken down into three specific objectives (SO), namely: \r\nSO1: To identify the media news frames of the securitization of the \"migration crisis\" in Chilean mainstream press during 2014-2026.\r\nSO2: To analyze the consolidation of media news frames of the securitization of the \"migration crisis\" in Chilean mainstream press during 2014-2026. \r\nSO3: To compare the media news frames of the securitization of the \"migration crisis\" between the Northern, the Southern, and the Metropolitan Regions' mainstream press during 2014-2026.\r\nThe empirical part includes the analysis of all informative pieces concerning the issues of security and immigration collected from the national editions of seven leading Chilean newspapers published in the Northern, Metropolitan, and Southern regions throughout a decade timespan (2014-2026). Such an elaborate dataset will reveal systematic longitudinal analysis across time, regions, and media outlets, providing a profound understanding of Chile's securitization of the \"migration crisis.\" \r\nThe proposed methodological paths for each SO are:  SO1 will employ news framing analysis (de Vreese, 2005; Mu\u00f1iz, 2011) to identify the media coverage frames of the securitization of the \"migration crisis,\" applying a manual qualitative content analysis using Atlas. Ti 23 software for better coding manageability (Kovar, 2023; V\u00e1zquez-Herrero et al., 2022; Sarah-Liu, 2021). We will follow an inductive approach in which frames emerge from the collected corpus in situ (Semetko & Valkenburg, 2000) since it broadens the possibility of discovering a more amplified list of frames, thus contributing to a deeper analysis of the issue. SO2 will use a frequency analysis in Atlas.ti 23 and in Microsoft Excel (v2023) to identify and examine the most prominent media frames over the selected period. SO3 will follow a comparative analysis (Collier, 1993) to define similarities and\/or differences between a) different media conglomerates (El Mercurio S.A.P and COPESA S.A) and independent outlets (Publimetro) and b) the Northern, the Metropolitan, and the Southern regions over the selected period. In addition, our longitudinal data (2014-2026) allows us to study possible changes in media framing covering the migration-security nexus over a decade, providing a comprehensive study on the issue currently under development across the national mainstream press.\r\nThe main expected result is the generation of empirical evidence that advances understanding of the dominant frames of the securitization of the \"migration crisis\" in Chile. Given that most of the previous and current research on media securitization of migration has been EU or US-centered, our project calls for de-Westernizing this issue by contributing to a Latin American perspective to expand the geographical reach of research beyond European and US borders. As such, it offers new insights into the complexities of the securitization of the \"migration crisis\" in Chilean media and will contribute to the area of &#8203;&#8203;Communication and Social Studies and anyone interested in migration and security issues. Likewise, since the securitization of migration reinforces a politics of fear and racism (Wodak, 2015), our findings may also concern the Ministry of the Interior and Public Security, which is responsible for public policies and laws regarding immigration. The association of migration with security can be reflected in laws and policies that the country may adopt toward migrants through limiting access to certain nationalities, changes in visa procedures, higher security controls, and, most importantly, deterioration of the rights of migrants (Planas Gifra, 2024).\r\nFinally, as this project will empirically identify migration-security patterns in the mainstream press and track their evolution, identifying potential shifts over a decade's time span, it will help us raise public and service awareness in Chile by generating policy papers, infographics, and seminars for the lay public and opinion columns in local and national media, among others.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11250237<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2025 - Abril 2028<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26556\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Implications for an adipose tissue-ear axis in obesity-induced hearing loss: role of cochlear Nrf2\/ARE and NF-kB pathways\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26556\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26556\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Implications for an adipose tissue-ear axis in obesity-induced hearing loss: role of cochlear Nrf2\/ARE and NF-kB pathways[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1251159<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26654\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Slope-based Variational Analysis and Optimization\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26654\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26654\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Slope-based Variational Analysis and Optimization[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 3250857<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2025 - Marzo 2028<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26656\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Structural properties of Wasserstein spaces and applications to optimization\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26656\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26656\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Estudio de propiedades m\u00e9tricas y estructurales de los espacios de Wasserstein  (provenientes de la teor\u00eda de transporte \u00f3ptimo), y b\u00fasqueda de aplicaciones en optimizaci\u00f3n bajo incertidumbre.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Patrocinante<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26720\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Media Framing of the Securitization of &quot;Migration Crisis&quot; in Chile: A longitudinal study of the national mainstream press, 2014-2026.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26720\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26720\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The nation-state is an organization defined by two principles: its interests (e.g., political, economic, cultural) and its security. Therefore, states constantly seek survival, in which security plays a prominent role, surpassing all other issues (Waltz, 1979). The extent to which the movement of people across international borders has become a security issue is evident in how the migration-security nexus is prevalent in the current public and media debate around the globe, including Chile. This proposal stands on the premise that in a democratic society, mainstream media press is a highly significant actor in influencing levels of public concern and shaping people's attitudes towards social developments and phenomena, including migration and its securitization (Scherman et al., 2022; Ekman & Krzyzanowski, 2021). The representation of immigrants in mainstream media press creates opportunities for immigrants to either become part of society or be excluded from the public sphere. \r\nThe main objective of this proposal is to analyze the media framing of the securitization of the \"migration crisis\" in the Chilean mainstream media press during 2014-2026. Further on, this main objective is broken down into three specific objectives (SO), namely: \r\nSO1: To identify the media news frames of the securitization of the \"migration crisis\" in Chilean mainstream press during 2014-2026.\r\nSO2: To analyze the consolidation of media news frames of the securitization of the \"migration crisis\" in Chilean mainstream press during 2014-2026. \r\nSO3: To compare the media news frames of the securitization of the \"migration crisis\" between the Northern, the Southern, and the Metropolitan Regions' mainstream press during 2014-2026.\r\nThe empirical part includes the analysis of all informative pieces concerning the issues of security and immigration collected from the national editions of seven leading Chilean newspapers published in the Northern, Metropolitan, and Southern regions throughout a decade timespan (2014-2026). Such an elaborate dataset will reveal systematic longitudinal analysis across time, regions, and media outlets, providing a profound understanding of Chile's securitization of the \"migration crisis.\" \r\nThe proposed methodological paths for each SO are:  SO1 will employ news framing analysis (de Vreese, 2005; Mu\u00f1iz, 2011) to identify the media coverage frames of the securitization of the \"migration crisis,\" applying a manual qualitative content analysis using Atlas. Ti 23 software for better coding manageability (Kovar, 2023; V\u00e1zquez-Herrero et al., 2022; Sarah-Liu, 2021). We will follow an inductive approach in which frames emerge from the collected corpus in situ (Semetko & Valkenburg, 2000) since it broadens the possibility of discovering a more amplified list of frames, thus contributing to a deeper analysis of the issue. SO2 will use a frequency analysis in Atlas.ti 23 and in Microsoft Excel (v2023) to identify and examine the most prominent media frames over the selected period. SO3 will follow a comparative analysis (Collier, 1993) to define similarities and\/or differences between a) different media conglomerates (El Mercurio S.A.P and COPESA S.A) and independent outlets (Publimetro) and b) the Northern, the Metropolitan, and the Southern regions over the selected period. In addition, our longitudinal data (2014-2026) allows us to study possible changes in media framing covering the migration-security nexus over a decade, providing a comprehensive study on the issue currently under development across the national mainstream press.\r\nThe main expected result is the generation of empirical evidence that advances understanding of the dominant frames of the securitization of the \"migration crisis\" in Chile. Given that most of the previous and current research on media securitization of migration has been EU or US-centered, our project calls for de-Westernizing this issue by contributing to a Latin American perspective to expand the geographical reach of research beyond European and US borders. As such, it offers new insights into the complexities of the securitization of the \"migration crisis\" in Chilean media and will contribute to the area of &#8203;&#8203;Communication and Social Studies and anyone interested in migration and security issues. Likewise, since the securitization of migration reinforces a politics of fear and racism (Wodak, 2015), our findings may also concern the Ministry of the Interior and Public Security, which is responsible for public policies and laws regarding immigration. The association of migration with security can be reflected in laws and policies that the country may adopt toward migrants through limiting access to certain nationalities, changes in visa procedures, higher security controls, and, most importantly, deterioration of the rights of migrants (Planas Gifra, 2024).\r\nFinally, as this project will empirically identify migration-security patterns in the mainstream press and track their evolution, identifying potential shifts over a decade's time span, it will help us raise public and service awareness in Chile by generating policy papers, infographics, and seminars for the lay public and opinion columns in local and national media, among others.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26760\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            How do minority groups in Chile relate to and position themselves when interacting with the police? An analysis of procedural justice and motivational postures\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26760\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26760\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]In democratic countries, the effectiveness of police work relies on having public support. When the public believes in the police's legitimate authority, they are likelier to follow their orders and cooperate with law enforcement. Conversely, perceptions of unjust behavior, such as not allowing citizens to explain themselves during interactions (procedural injustice), can lead to defiance of police orders (defiant motivational postures). In fact, over recent decades, we have witnessed numerous violent protests, police brutality, and human rights violations by police forces worldwide, including in Chile. The Carabineros, Chile's primary police force, were once highly trusted by the Chilean population. However, incidents of corruption and excessive use of force during the October 2019 social outbreak severely damaged public trust in the police (Instituto Nacional de Derechos Humanos [INDH], 2021). Therefore, it is crucial to understand the extent to which individuals perceive the police as acting fairly and correctly (i.e., procedural justice) and how they interact with and view the police in Chile (i.e., motivational postures). Additionally, it is well documented in the international literature that people who belong to minority groups (such as migrants, indigenous people, black Americans, among others) may have more tense interactions with the police and suffer higher levels of discrimination when interacting with police officers. Particularly, in Chile, there is evidence that police forces have used, both historically and in the present day, excessive use of force in particular against minority groups, namely among Mapuche people, immigrants living in Chile, as well as youths from low socioeconomic backgrounds. Therefore, we argue that these interactions between citizens and police are not only theoretically significant but also have societal implications, potentially influencing levels of conflict or cohesion within a community.\r\nFurthermore, international studies have also shown that disproportionate use of force by law enforcement often targets marginalized communities, particularly minority groups. Members of these groups also experience higher levels of discrimination compared to more privileged social groups within specific contexts (Feldman et al., 2019; Gee & Ford, 2011). Such experiences erode trust in law enforcement and may provoke protests against the police or demands for police reforms, as well as the avoidance of the police, even their work may be necessary (Woods et al., 2015). Therefore, understanding the interplay between perceptions of procedural justice (Lind & Tyler, 1988; Tyler & Lind, 1992) and motivational postures (Braithwaite, 2003) is crucial for understanding police-minority interactions.\r\nIn this light, the current project aims to understand how police-minority interactions in Chile are experienced and perceived in terms of procedural justice and motivational postures by considering the perspectives of three minority groups (namely, Mapuche people, immigrants living in Chile, and youths from low socioeconomic backgrounds) and police officers.\r\nTo our knowledge, there is a scarcity of studies focusing on police-minority interactions in Chile. Thus, by developing three interconnected studies with minority group members (Studies 1 and 3) and police officers (Study 2), this project\u0092s expected results aim to, firstly, contribute to the state-of-the-art from a theoretical perspective, with the aim of advancing our understanding of police-minority interactions, through a combination of different frameworks combining procedural justice and motivational postures. Second, from a practical standpoint, we aim to generate empirical evidence that enables our understanding of police- minority interactions and provide practical guidelines and public policy recommendations about ways in which minority-police interactions can improve and lead to higher levels of procedural justice and more compliance with law enforcement.\r\nTo achieve our main objective, we will conduct three interconnected studies. First, we will implement a longitudinal qualitative analysis through focus groups with minority group members (Study 1). Secondly, we will conduct semi-structured interviews with police officers (Study 2) and, finally, we will conduct an experimental study to test the causal relationship between procedural justice and motivational postures from the perspective of minority group members (Study 3). Data will be collected in the North (Antofagasta), Center (Santiago) and South (Temuco) of Chile).\r\nWe expect to publish four articles in peer-reviewed journals, organize three academic seminars with national and international scholars, and present our findings in different national and international conferences. We will also organize four dissemination activities with policy makers and Human Rights Organizations concerned with police violence and how this phenomenon particularly affects minority groups, as a means to contribute to and potentially influence the development of public policies in the area of police- minority interactions. Finally, we also aim to disseminate our results among Carabineros and other relevant actors within Chilean society, as well as civil society in general.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26776\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Boosting Nitrogen Use Efficiency with Biochar-based Controlled-Release Fertilizer: A Pathway from Soil to Plant and Sustainability to Productivity\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26776\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26776\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]We propose a three-stage study to explore the roles of BCRNF on NUE, wheat productivity, and nutritional grain quality. In Stage 1, we will assay the effect of BCRNFs on N-dynamics and chemical soil properties through soil incubations performed under controlled conditions for 90 days. We will measure N-losses periodically through volatilization of NH3 and NO2. Additionally, we will quantify potentially mineralizable nitrogen (PMN), changes in the C:N ratio, and changes in pH and soil nutrient content during nine sampling dates. In Stage 2, two independent experiments will be conducted to evaluate the interaction among BCRNFs with soil and its effect on the morphological, physiological, and biochemical plant adaptive strategies related to NUE. In Experiment 1, wheat will be harvested at the pre-anthesis growth stage, and plant growth parameters and N concentration in tissues will be used to determine N uptake efficiency (NUPE). Additionally, it will measure plant adaptative strategies related to N-uptake, such as root architecture, exudation of organic acids by roots, and changes in enzymatic and microbial activities in the soil. In Experiment 2, wheat plants will be harvested at the maturity stage to evaluate the relationship between grain yield and N concentration to determine N utilization efficiency (NUTE). Plant adaptive strategies related to NUTE will also be assessed, including N-translocation and remobilization, CO2 assimilation rate (A), stomal conductance (gs), photosynthesis per unit of N, PNUE. In addition, the leaf response to the fluorescence and stay green trait will also be performed. The amount of nitrogen in grain derived from the fertilizer (Ndff) will be calculated using the &#948;15N values obtained from grains. In Stage 3, the effect of BCRNFs on wheat productivity and nutritional quality will be evaluated in field conditions. The trials will be conducted over two agricultural seasons, and the impact of BCRNFs on soil and plant samples will be assessed at three different stages: anthesis, soft dough grain, and hard dough grain. During these stages, the chemical properties of the soil, as well as microbial and enzymatic activities, will be evaluated. Photosynthetic parameters such as A, gs, Ci, E, Fo, Fm, and QY will be quantified. The plant height, harvest index, and yield components will be assessed at the end of each growing season. Grain quality indicators like protein content, gluten levels, and sedimentation rate will also be measured. Finally, the amount of nitrogen in grain derived from the fertilizer (Ndff) will be calculated using the &#948;15N values obtained from grains. This proposal focused on understanding the interconnections among soil, N-fertilizer, and plant physiology, using wheat as a model crop. The primary aim is to boost N management strategies in agriculture, ensuring a balance between productivity and sustainability. The initiative seeks to create a technological solution to enhance NUE, reduce environmental impact, and ensure global food security.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1251945<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2025 - Abril 2029<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26844\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Social, technological, and health explorations of the uses of wearable technologies in Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26844\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26844\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]This research aims to explore the everyday interactions and relationships among individuals who use wearable technologies in Chile, focusing on health self-tracking and its implications.\r\nWearable technologies, which integrate advanced computing and electronics into clothing and accessories, have seen significant global adoption since the early 21st century due to the miniaturization of computational devices. These technologies offer continuous, fluid, and hands-free operations, transforming them into an extension of the body and mind. Their applications span various domains, including health and fitness, medical applications, consumer electronics, military uses, and fashion. Despite their benefits, wearable technologies present technical and ethical challenges, particularly concerning privacy, data analysis, and surveillance.\r\nIn Chile, wearable devices are increasingly used to monitor health variables, although detailed data on their adoption rates among the general population is limited. Studies indicate a growing interest in integrating these technologies into healthcare practices, suggesting potential widespread use in the near future.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26916\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            The School\u0092s Role in Shaping Attitudes Towards Inequality:  An In-depth Inquiry in Schools with Socioeconomically Diverse Students\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26916\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26916\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The school is a crucial socialisation institution that forms young people\u0092s perceptions, attitudes, and beliefs (Gidengil et al., 2016). Moreover, it is the main socialisation space that provides the youth with broader social relationships compared to the intimate social context of the family (Vincent et al., 2018). This Fondecyt project will ethnographically analyse the school\u0092s role in socialising attitudes towards socioeconomic inequality among secondary students in classrooms with a diversified socioeconomic composition. Studying these attitudes is crucial since they might symbolically legitimise or challenge the existing social order (Sandel, 2021) and contribute to the reproduction or transformation of socioeconomic inequalities (Alesina et al., 2012). Since evidence on this issue is key for democratic governments in socioeconomically unequal societies to inform policies for reducing inequality and increasing social cohesion, the project focuses on Chile, a country with extreme levels of socioeconomic inequality (WID, 2022). By identifying opportunities and challenges for schools to promote egalitarian attitudes towards socioeconomic inequality among their socioeconomically diverse students, the project will provide decisive evidence for education policy to improve their support to school communities. \r\n\r\nThe general objective of this project is to analyse how the schools contribute to shaping attitudes towards socioeconomic inequality among secondary students in classrooms that have diversified their socioeconomic composition. The specific objectives are as follows:\r\n1. To characterise the socioeconomic heterogeneity within schools with secondary education in Chile and identify those that have diversified the socioeconomic composition of their students in the last decade. \r\n2. To determine the schools\u0092 pedagogical, organisational and community responses to the increase in their socioeconomic diversity and examine how these responses promote particular attitudes towards socioeconomic inequality. \r\n3. To describe the students' inter-class relationships and identify how these relate to particular attitudes towards socioeconomic inequality, including awareness of inequality, perceptions of the fairness of social inequalities, meritocratic beliefs, and egalitarian preferences.\r\n\r\nThe study will use a sequential mixed methods design, with a first quantitative phase aimed at answering Specific Objective 1 and informing the selection of the sample of schools for the second - ethnographic - phase, which is the predominant one and seeks to answer Specific Objectives 2 and 3:\r\na) Quantitative phase: A Socioeconomic Diversity Index (SDI) will be created using data from the Quality of Education Agency through its SIMCE questionnaire to parents of secondary students for 2014-2024, which asks about the families\u0092 socioeconomic information. Descriptive statistics will be used to describe SDI and its temporal variation by school.\r\nb) Ethnographic phase: Ethnographic fieldwork will be deployed in three schools with increased socioeconomic diversity, as measured in the SDI. Fieldwork in each school will last approximately two months, and the following methods will be used:\r\n- Interviews with staff members: 10 in each school (30 total), including the Principal, two Deputy Principals, three professionals from a psychosocial support team and four teachers.\r\n- Friendship maps and interviews with students: Maps of the students\u0092 social relationships will be built with secondary students, seeking to include the whole class in each school (approximately 100 students in total). Maps will be followed by interviews.\r\n- Observations: They will be conducted in classrooms, playgrounds, and school events for approximately 100 hours in each school (approximately 300 hours of observation in total).\r\n\r\nThe expected results include a) a map of all Chilean schools according to their current socioeconomic diversity and its temporal variation; b) in-depth evidence of inter-class relationships between secondary students and how these affect their attitudes towards socioeconomic inequality; and c) a systematisation of the schools\u0092 responses to the students\u0092 socioeconomic heterogeneity, their links to the development of attitudes towards socioeconomic inequality, and their facilitating and hindering elements. These findings will be useful for other schools that are diversifying their student body, wish to do so, or are interested in promoting egalitarian attitudes among their students. Ultimately, the project will provide critical evidence for public policy to promote schools that foster the development of egalitarian attitudes and potentially contribute to reducing social inequalities.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26990\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            How do minority groups in Chile relate to and position themselves when interacting with the police? An analysis of procedural justice and motivational postures\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26990\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26990\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]In democratic countries, the effectiveness of police work relies on having public support. When the public believes in the police's legitimate authority, they are likelier to follow their orders and cooperate with law enforcement. Conversely, perceptions of unjust behavior, such as not allowing citizens to explain themselves during interactions (procedural injustice), can lead to defiance of police orders (defiant motivational postures). In fact, over recent decades, we have witnessed numerous violent protests, police brutality, and human rights violations by police forces worldwide, including in Chile. The Carabineros, Chile's primary police force, were once highly trusted by the Chilean population. However, incidents of corruption and excessive use of force during the October 2019 social outbreak severely damaged public trust in the police (Instituto Nacional de Derechos Humanos [INDH], 2021). Therefore, it is crucial to understand the extent to which individuals perceive the police as acting fairly and correctly (i.e., procedural justice) and how they interact with and view the police in Chile (i.e., motivational postures). Additionally, it is well documented in the international literature that people who belong to minority groups (such as migrants, indigenous people, black Americans, among others) may have more tense interactions with the police and suffer higher levels of discrimination when interacting with police officers. Particularly, in Chile, there is evidence that police forces have used, both historically and in the present day, excessive use of force in particular against minority groups, namely among Mapuche people, immigrants living in Chile, as well as youths from low socioeconomic backgrounds. Therefore, we argue that these interactions between citizens and police are not only theoretically significant but also have societal implications, potentially influencing levels of conflict or cohesion within a community.\r\nFurthermore, international studies have also shown that disproportionate use of force by law enforcement often targets marginalized communities, particularly minority groups. Members of these groups also experience higher levels of discrimination compared to more privileged social groups within specific contexts (Feldman et al., 2019; Gee & Ford, 2011). Such experiences erode trust in law enforcement and may provoke protests against the police or demands for police reforms, as well as the avoidance of the police, even their work may be necessary (Woods et al., 2015). Therefore, understanding the interplay between perceptions of procedural justice (Lind & Tyler, 1988; Tyler & Lind, 1992) and motivational postures (Braithwaite, 2003) is crucial for understanding police-minority interactions.\r\nIn this light, the current project aims to understand how police-minority interactions in Chile are experienced and perceived in terms of procedural justice and motivational postures by considering the perspectives of three minority groups (namely, Mapuche people, immigrants living in Chile, and youths from low socioeconomic backgrounds) and police officers.\r\nTo our knowledge, there is a scarcity of studies focusing on police-minority interactions in Chile. Thus, by developing three interconnected studies with minority group members (Studies 1 and 3) and police officers (Study 2), this project\u0092s expected results aim to, firstly, contribute to the state-of-the-art from a theoretical perspective, with the aim of advancing our understanding of police-minority interactions, through a combination of different frameworks combining procedural justice and motivational postures. Second, from a practical standpoint, we aim to generate empirical evidence that enables our understanding of police- minority interactions and provide practical guidelines and public policy recommendations about ways in which minority-police interactions can improve and lead to higher levels of procedural justice and more compliance with law enforcement.\r\nTo achieve our main objective, we will conduct three interconnected studies. First, we will implement a longitudinal qualitative analysis through focus groups with minority group members (Study 1). Secondly, we will conduct semi-structured interviews with police officers (Study 2) and, finally, we will conduct an experimental study to test the causal relationship between procedural justice and motivational postures from the perspective of minority group members (Study 3). Data will be collected in the North (Antofagasta), Center (Santiago) and South (Temuco) of Chile).\r\nWe expect to publish four articles in peer-reviewed journals, organize three academic seminars with national and international scholars, and present our findings in different national and international conferences. We will also organize four dissemination activities with policy makers and Human Rights Organizations concerned with police violence and how this phenomenon particularly affects minority groups, as a means to contribute to and potentially influence the development of public policies in the area of police- minority interactions. Finally, we also aim to disseminate our results among Carabineros and other relevant actors within Chilean society, as well as civil society in general.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2025 - Marzo 2028<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27000\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Determination of magma fertility and sulfide saturation for giant porphyry copper deposits in central Chile: A platinum-group element perspective\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27000\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27000\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Uso de la qu\u00edmica de elementos altamente sider\u00f3filos y calc\u00f3filos para discriminar rocas asociadas a yacimientos minerales productivos[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Patrocinante<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1251159<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27019\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Slope-based Variational Analysis and Optimization\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27019\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27019\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Slope-based Variational Analysis and Optimization[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 3250857<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2025 - Marzo 2028<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27020\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Structural properties of Wasserstein spaces and applications to optimization\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27020\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27020\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Estudio de propiedades m\u00e9tricas y estructurales de los espacios de Wasserstein  (provenientes de la teor\u00eda de transporte \u00f3ptimo), y b\u00fasqueda de aplicaciones en optimizaci\u00f3n bajo incertidumbre.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1251064<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2025 - Enero 2028<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27042\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Soil microbial community structure and carbon and nitrogen functionality responses to combined effects of drought and fires in Mediterranean forest ecosystems\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27042\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27042\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Climate projections anticipate an increase in frequent droughts, episodes of extreme fire behavior, in addition to heat waves and unstable atmospheric conditions, all phenomena related to climate change. Drought intensification has been projected to increase in frequency in several regions across the globe, including the southwestern part of South America, the European Mediterranean Basin, Northern Africa, the Middle East, Central Asia, Australia, and the USA. Particularly, the former three areas have been recognized as locations highly likely to face unprecedented droughts during the 21st century, and within Southwestern South America, Chile has been alarmingly pointed out as the country earlier in this era experiencing this phenomenon, regardless of the greenhouse gas emissions scenario. Catastrophic effects such as extreme droughts and changes in fire behavior are important drivers of ecosystem degradation in arid, semiarid, dry temperate and Mediterranean ecosystems. Mediterranean ecosystems of central Chile have been indicated as the earliest in its type experiencing effects of climate change; where an accelerated aridification is already registered; therefore, representing a scenario to anticipate the effects of climate anomalies at other ecosystems of its type. Persistent droughts and land burning can compromise belowground conditions that are essential to support aboveground life in terrestrial ecosystems. Nevertheless, despite their importance for ecosystem functioning and recovery after environmental disturbances, there still a considerable lack of comprehension on how belowground attributes respond to combined stressors such as droughts and fires. This is of particular concern in conditions where post-fire plant and soil recovery have been shown to be inhibited or retarded due to severe droughts. Therefore, this project aims to evaluate individual and combined effects of drought and fires over time in soil microbial communities and carbon and nitrogen functional dynamics along with the relationship of these attributes and the state of sclerophyll vegetation in Mediterranean forests of central Chile. To accomplish this goal a multiscale approach will be applied in this research by integrating scientific disciplines from landcape ecology to molecular biology. By using remote sensing study site will be selected within an area known to be affected by an extended drought period (since 2010), in addition to hyper-dry years (2019 and 2021), which in addition has experienced the occurrence of historical wildfires as the case of 2017. From this initial screening \r\n18 study conditions resulting from three climate anomaly categories identified (high, medium, low) according to differences in precipitation with respect to historical average, three categories for forest response to drought (recovered, unaffected and unrecovered) based on analysis of Normalized Burn Index (NBR = [NIR - SWIR] \/ [NIR + SWIR]) and two burned conditions (with and without) will be obtained for soil and vegetation assessments. Classical soil physicochemical analyses and NG-sequencing techniques including high-throughput amplicon sequencing (metabarcoding), whole genome sequencing (metagenomics), and gene expression (metatransciptomics), in addition to soil physiological analyses will be performed. Moreover, vegetation recovery following drought and fire will be evaluated. Results from this study will allow to better understand the individual versus the combined effects of drought and fires in soil microbial community structure and carbon and nitrogen functionality, which are expected to be exacerbated with the combined occurrence of these phenomena, giving insights on the resilience capacity of soil microbiomes and carbon and nitrogen biogeochemical cycles. From this work, results will also allow to gain a more comprehensive understanding of the linkages between soil functionality and vegetation responses to drought and fires over time, which will allow to identify ecological drivers related to ecosystem stability.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11251528<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2025 - Marzo 2028<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27068\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            HAMFLIP: Hamiltonicity and Diameter of Flip Graphs\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27068\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27068\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Combinatorial objects frequently appear in various areas of computer science and discrete\r\nmathematics. These objects are central to questions in algorithmic design, where we aim to program a\r\ncomputer to efficiently perform tasks involving them. These tasks may include counting objects based on\r\ncertain parameters, sampling an object uniformly at random, optimizing with respect to an objective\r\nfunction, searching for objects that satisfy specific properties, or generating all objects exactly once. This\r\nproject focuses on two of these problems: combinatorial generation and the search for highly distinct\r\ncombinatorial objects.\r\nWhile many of the aforementioned tasks have general-purpose techniques that allow them to tackle\r\nmultiple problems simultaneously, the situation becomes less clear when dealing with combinatorial\r\ngeneration or the search for distant objects. Much of the effort in these areas has been devoted to\r\ndeveloping ad hoc methods. Despite this, these last two problems can be naturally phrased in the language\r\nof flip graphs, which encode the similarity between combinatorial objects. In this context, the problem\r\ntransforms into the traditional graph problems of Hamiltonicity (finding a path that traverses all the\r\nvertices exactly once) and diameter (finding two vertices that are farthest apart). Recent research has\r\nhighlighted the significant value of exploiting polytopal properties and symmetry of flip graphs, leading to\r\nunified frameworks that can address many problems simultaneously. The main objective of this project is\r\nto contribute to this perspective. Specifically, it aims to enhance our understanding of the polytopal and\r\nsymmetric properties of flip graphs and use this knowledge to develop efficient algorithms for tackling\r\nHamiltonicity and diameter problems[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1251905<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2025 - Marzo 2028<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27076\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Real-time characterization of microstructural changes of metals under uniaxial tension: A nonlinear acoustics approach.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27076\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27076\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The primary objective of this research is to evaluate the feasibility of using ultrasonic acoustic imaging as a\r\nnon-intrusive, in situ technique to assess the plastic behavior of commercial metals and alloys. Specifically,\r\nit aims to explore the potential of ultrasonic acoustic imaging to identify and monitor various plastic\r\ndeformation mechanisms in stainless steel and aluminum. The selection of materials is based on their distinct\r\nplastic deformation behaviors: aluminum releases internal energy through dislocation mechanisms, while\r\nstainless steel releases energy through deformation, first by dislocation and then by twinning. To achieve\r\nthis goal, the study will continuously measure changes in sound velocity and the nonlinear acoustic parameter\r\n&#946; while subjecting the materials to uniaxial tensile tests at different levels of applied stress.\r\nPrevious studies conducted by our research group have demonstrated that changes in sound velocity, in\r\nrelation to strain, offer a reliable means of quantifying dislocation density in local measurements on\r\naluminum, copper, and stainless steel specimens. Furthermore, these studies have observed that alterations\r\nin the nonlinear acoustic parameter, specifically second harmonic generation, exhibit more pronounced\r\nchanges compared to variations in linear acoustics (speed of sound). Building upon these findings, the\r\nproposed research involves the generation of both linear and nonlinear acoustic images over wider spatial\r\nregions to advance our understanding of the plastic behavior of materials undergoing different\r\nmicrostructural changes.\r\nThe challenge of applying the results of this research to in situ measurements in the industry is not trivial,\r\nas the highly controlled laboratory conditions are not maintained in service components. In this regard, the\r\nincorporation of machine learning tools in the proposal aims to identify the parameters most sensitive to the\r\nvarious deformation mechanisms through clustering techniques. It is expected that the correlation of different\r\nacoustic parameters with the various plastic deformation mechanisms of both materials under study will\r\ngenerate an optimal database that reflects the variety of scenarios present in service components, thus\r\npaving the way for the industrial use of the proposed characterization system.\r\nThe adoption of diagnostic techniques and the utilization of metallic material state analysis in service\r\nsignificantly enhance our ability to comprehend and control plastic deformation mechanisms, contributing to\r\nimproved material reliability and robustness, and facilitating informed decision-making and maintenance\r\nstrategies.\r\nAdditionally, ex-situ standard microstructural tests, including XRD (X-ray diffraction), EBSD (electron\r\nbackscatter diffraction), and TEM (transmission electron microscopy), will be performed to characterize the\r\nmaterial\u0092s state after deformation. These complementary tests will provide valuable microstructural\r\ninformation, enabling the correlation of deformation states with the acquired acoustic images.\r\nAll the acoustic and microstructural information described above, in conjunction with previous research group\r\ndata, will be stored in a robust and comprehensive database. This database will serve as the input for a\r\nMachine Learning algorithm, which will facilitate the identification of patterns of correspondence between\r\nacoustic and microstructural parameters. This approach aims to enable the future prediction, with a high\r\nlevel of probability, of the specific type of plastic deformation mechanism that a material is undergoing based\r\non the acoustic parameter measurements.\r\nThe successful development of this research proposal would yield several significant outcomes. Firstly, it\r\nwould enable the early detection of microstructural changes in materials long before fractures occur.\r\nMoreover, it would establish a non-intrusive tool for characterizing materials by identifying the underlying\r\nmechanisms driving plastic deformation and monitoring the evolution of materials in service over time.\r\nUltimately, this research has the potential to advance our understanding of the plastic behavior of stainless\r\nsteel and aluminum, opening avenues for improved analysis, design, and performance evaluation of materials\r\nin various industrial applications.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1250472<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2025 - Marzo 2029<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27077\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            The stability of austenite in medium Mn steels\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27077\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27077\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Medium manganese steels (MMnS) are currently a subject of active scientific research due to a number of\r\nreasons. First, their unique combination of strength and ductility makes them promising candidates for\r\nlightweight structural applications in automotive and aerospace industries, where reducing weight without\r\nsacrificing mechanical properties is critical. Second, their ability to retain austenite at room temperatures\r\noffers advantages in terms of formability and resistance to hydrogen embrittlement, which are significant\r\nchallenges in steel manufacturing. Third, medium Mn steels have shown potential in enhancing wear and\r\nimpact resistance, making them suitable for applications in mining, construction, and machinery sectors.\r\nAdditionally, their corrosion resistance and potential for cost-effective alloying with other elements further\r\nexpand their utility across various engineering fields. Scientific research on medium Mn steels aims to\r\noptimize their microstructure, processing parameters, and alloy compositions to unlock their full potential,\r\nthereby contributing to the development of advanced materials that meet the performance requirements of\r\nmodern industries while promoting sustainability and efficiency in manufacturing processes.\r\nThe proposed research aims to investigate the stability of austenite in medium manganese steels within\r\nternary Fe-C-Mn and Fe-C-Mn-X systems (X: Al, Si, Cr), focusing on its correlation with processing\r\nparameters. The primary objective is to assess the stability of austenite via (i) experimentally determining\r\nthe martensite start temperature (thermal stability) using dilatometry and thermal analysis techniques, and\r\n(ii) to evaluate the fraction of austenite as a function of strain (mechanical stability) under tensile test. These\r\nmeasurements will provide crucial data to understand how variations in processing conditions influence\r\naustenite stability. Else, the study will correlate austenite stability with mechanical properties through\r\nmechanical tests and in-depth microstructural characterization, aiming to establish predictive models.\r\nAdditionally, thermodynamic and kinetic calculations will aid in assessing the phase transformation behavior\r\nunder different thermal histories. The research will extend its scope to evaluate impact and wear properties\r\nin relation to austenite stability, crucial for applications in industries requiring high strength and toughness,\r\nsuch as mining and construction.\r\nBy systematically exploring these relationships, the project seeks to advance the fundamental understanding\r\nof medium Mn steels, potentially leading to the development of lightweight, durable materials with enhanced\r\nperformance characteristics. Ultimately, the findings aim to contribute to the optimization of steel\r\nmanufacturing processes and the realization of more efficient and reliable engineering solutions in demanding\r\noperational environments[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> Proyecto N\u00ba 3250704<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2025 - Diciembre 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27080\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fondecyt de Postdoctorado 2025\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27080\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27080\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Fondecyt de Postdoctorado 2025 Proyecto N\u00ba 3250704, Universidad de Chile y Universidad de O'Higgins - Implementaci\u00f3n de la investigaci\u00f3n 'Exploraci\u00f3n de las bases neuroanat\u00f3micas de la alteraci\u00f3n del insight en la enfermedad de Alzheimer' como Investigador Postdoctoral[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2025 - Marzo 2028<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27086\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Determination of magma fertility and sulfide saturation for giant porphyry copper deposits in central Chile: A platinum-group element perspective\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27086\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27086\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Uso de la qu\u00edmica de elementos altamente sider\u00f3filos y calc\u00f3filos para discriminar rocas asociadas a yacimientos minerales productivos[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2025 - Septiembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Convenio Biodiversidad Codelco DET<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26382\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Evaluaci\u00f3n del Subsidio Ecol\u00f3gico de C\u00f3ndores y \u00c1guilas Chilenas en el Relleno Sanitario La Yesca, Regi\u00f3n de O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26382\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26382\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Evaluaci\u00f3n del Subsidio Ecol\u00f3gico de C\u00f3ndores y \u00c1guilas Chilenas en el Relleno Sanitario La Yesca, Regi\u00f3n de O'Higgins\"\r\n\r\nObjetivo General\r\nEvaluar el uso del relleno sanitario La Yesca por c\u00f3ndores y \u00e1guilas chilenas como un subsidio ecol\u00f3gico y caracterizar los patrones de actividad de estas especies en relaci\u00f3n con los residuos disponibles (a\u00fan la chica no sabe con cual especie trabajar\u00e1 porque no hemos visitado el lugar, pero algo asi estamos dise\u00f1ando).\r\n\r\nObjetivos Espec\u00edficos\r\nDeterminar la frecuencia y duraci\u00f3n de las visitas de c\u00f3ndores y \u00e1guilas chilenas al relleno sanitario La Yesca mediante el uso de c\u00e1maras trampa.\r\nIdentificar los patrones estacionales de actividad de c\u00f3ndores y \u00e1guilas chilenas en el relleno sanitario a lo largo del a\u00f1o.\r\nComparar el uso del relleno sanitario por ambas especies y analizar si existen diferencias en el comportamiento de aprovechamiento de recursos antropog\u00e9nicos.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2025 - Marzo 2029<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26860\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            &quot;From source to surface: deciphering the spatio-temporal evolution of a distributed volcanic field&quot;\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26860\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26860\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Monogenetic volcanoes are the most common expression of magmatism on the Earth\u0092s surface, and they are found in every tectonic setting, yet key aspects of the behavior and evolution of monogenetic volcanic systems remain poorly understood. Understanding the processes that govern the evolution of monogenetic volcanoes, and the timescales over which these processes operate, is critical for hazard assessment in active distributed volcanic fields.\r\nThe Southern Volcanic Zone (SVZ), one of the three volcanic regions of The Andes, displays a diverse landscape characterized by historically and potentially active volcanic structures, including ~60 large stratovolcanoes, three giant silicic caldera systems, and hundreds of small eruptive centers. Even these monogenetic volcanoes are considerably smaller in size and volume, they tend to be grouped in space and time, forming distributed volcanic fields, and provide information from source to surface processes that are usually obscured by the commonly dominant more evolved compositions in the Andean arc. Among the Holocene clustered small eruptive centers within the SVZ, this project focuses on the youngest distributed volcanic field in Chile, Carr\u00e1n-Los Venados, which includes not only the most recent monogenetic eruption in Chile, which occurred in 1979, but it also hosts two other historical eruptions in 1907 and 1955.\r\nThe Carr\u00e1n-Los Venados distributed volcanic field (CLV) has received limited attention, despite its\r\nplacement at position No. 9 in the specific risk ranking of active volcanoes in Chile compiled by\r\nSERNAGEOMIN in 2020. Past research on the CLV has mostly focused on chronicling and observing the impacts of the historic eruptions. While some studies have touched upon the geochemical and tectonic aspects of the region, there remains a distinct absence of a comprehensive and cohesive examination of the entire volcanic field. Therefore, building upon previous research conducted in CLV, this project aims to tackle this knowledge gap, and we propose to carry out a detailed multi-disciplinary study (physical volcanology, petrology\/geochemistry, and volcanic hazards). Primary research questions include: When did the volcanism start in CLV? What processes contribute to the formation of this volcanism, and what are the magmatic factors that influence its evolution? Where does the volcanic activity take place, and how does it\r\nmanifest on the surface? What should we expect in the next eruption? To answer these questions, we propose a methodology based on deposit characterization and mapping, geochronology, morphometry, rheology, petrography, mineral chemistry, geothermobarometry and hygrometry, and geochemical characterization and modelling. The integration of these diverse datasets will provide key constraints on the sources, processes, and timescales of magma ascent and storage leading to eruption of the CLV clustered small eruptive centers and small stratovolcanoes, providing an important framework for better understanding the behavior of distributed volcanic fields globally.\r\nFurthermore, this project aims to provide valuable support to undergraduate and graduate students, who will have the unique opportunity to engage in all aspects of this research project, making it a significant component of their dissertation studies. Additionally, the study will foster ongoing international collaboration, creating avenues for future student and faculty exchanges. Moreover, it will facilitate outreach educational initiatives for the local community, including specialized seminars, thereby promoting knowledge dissemination and interactive learning experiences.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 17054<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2025 - Junio 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26534\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Mujeres privadas de libertad en la regi\u00f3n de O\u0092Higgins: experiencias, tensiones y desaf\u00edos desde una perspectiva de g\u00e9nero.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26534\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26534\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Chile es uno de los pa\u00edses de Am\u00e9rica Latina y el Caribe con mayor poblaci\u00f3n femenina privada de libertad recluida en centros penitenciarios. Del total de la poblaci\u00f3n que se encuentra en estas condiciones, el 11,2% corresponde a mujeres. Situaci\u00f3n que pone de manifiesto una serie de adversidades que deben sortear las mujeres privadas de libertad, producto del actual sistema penitenciario en Chile. \r\nEn ese sentido, alerta de sobremanera la vulneraci\u00f3n de los derechos sexuales y reproductivos de las mujeres privadas de libertad, as\u00ed lo hizo saber el Informe del Subcomit\u00e9 para la Prevenci\u00f3n de la Tortura y Otros Tratos o Penas Crueles, Inhumanos o Degradantes, respecto al impacto psicol\u00f3gico que genera en las mujeres la separaci\u00f3n con sus hijos\/as durante la prisi\u00f3n preventiva. \r\nAs\u00ed mismo, el informe a\u00f1ade las condiciones adversas en las cuales se encuentran los recintos penitenciarios afectando el bienestar psicol\u00f3gico, emocional, f\u00edsico y sexual de las mujeres, destaca la falta de acceso a los servicios de salud, la ausencia de recursos en materia de salud menstrual, la discriminaci\u00f3n por g\u00e9nero y orientaci\u00f3n sexual. \r\nLa realidad de las mujeres en el contexto penitenciario, ha sido un \u00e1mbito incipientemente abordado por la academia y precariamente problematizado en materia legislativa en Chile. Es por ello, que el presente proyecto busca indagar en esta materia desde la realidad de mujeres condenadas privadas de libertad en el complejo penitenciario de Rancagua, buscando conocer y analizar la discriminaci\u00f3n gen\u00e9rica, el estigma asociado a la identidad de g\u00e9nero y orientaci\u00f3n sexual, y las vicisitudes respecto a sus procesos de salud sexual, reproductiva, no reproductiva y afectiva; as\u00ed como proponer lineamientos en la intervenci\u00f3n de las mismas a partir de su propia experiencia a indagar.\r\nEl presente estudio utilizar\u00e1 un dise\u00f1o cualitativo, con elementos del paradigma fenomenol\u00f3gico feminista y de los conocimientos situados de las epistemolog\u00edas feministas. Para co-construir la informaci\u00f3n, se realizar\u00e1n entrevistas semiestructuradas, mapeos corporales y grupos de discusi\u00f3n. Para el an\u00e1lisis de la informaci\u00f3n obtenida se utilizar\u00e1 el an\u00e1lisis tem\u00e1tico cualitativo. \r\nComo resultados de este proyecto se prev\u00e9 una aproximaci\u00f3n situada a la realidad en materia de derechos sexuales y reproductivos de las mujeres privadas de libertad de la regi\u00f3n de O\u0092Higgins. A su vez, se espera establecer lineamientos de car\u00e1cter interventivo que permitan otorgar un abordaje situado en las necesidades de las participantes, en materia de derechos humanos, sexuales y reproductivos, y en temas afines. Por \u00faltimo, se prev\u00e9 mantener el v\u00ednculo para instancias colaborativas futuras que permitan un trabajo conjunto en estas tem\u00e1ticas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27036\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            N\u00facleo Milenio PhytoLearning\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27036\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27036\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto tiene como objetivo desarrollar e implementar modelos de aprendizaje autom\u00e1tico (Machine Learning, ML) para analizar datos \u00f3micos generados a partir de plantas agron\u00f3micas, con el fin de identificar patrones moleculares clave asociados a su productividad, resistencia a estreses abi\u00f3ticos (como sequ\u00eda y salinidad) y bi\u00f3ticos (como plagas y enfermedades), y su adaptaci\u00f3n a condiciones clim\u00e1ticas cambiantes.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11251927<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27037\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Post-Transcriptional Networks Driving Endemic Plant Resilience to Climate Change.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27037\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27037\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The main objective of this proposal is to study the miRNA:mRNA post-transcriptional regulatory networks in non-model plant species associated with the process of climate change stress resilience.The proposal integrates the development of computational algorithms, the use of massive data of public non-coding RNA sequences, and the use of a biological model to study post-transcriptional regulatory networks (at the genome-scale) in biological processes associated with climate resilience and adaptation of endemic plant species.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> VIU24P0043<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27055\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Producci\u00f3n Escalable de Inmunoestimulantes Nanoestructurados para el Control de Piscirickettsiosis en Salm\u00f3n del Atl\u00e1ntico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27055\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27055\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Producci\u00f3n Escalable de Inmunoestimulantes Nanoestructurados para el Control de Piscirickettsiosis en Salm\u00f3n del Atl\u00e1ntico[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> Fondecyt N\u00b0 1251797<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26510\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Between the Pacific and the Andes. The Intermediate Depression megapatch, a key late Pleistocene-early Holocene ecosystem for plants, animals and humans in the Atacama Desert\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26510\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26510\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]PROPOSAL ABSTRACT:\r\nTraditional archaeology proposes that the first settlers of South America moved preferentially along the\r\nAndes or the Pacific coast. Given that the Andean Puna (>3,000 masl) was an outstanding ecological\r\nmegapatch that concentrated similar resources throughout the Andes, it was an attractive migratory route.\r\nThis paved the way for the establishment of a unique Altiplano socio-ecological system, which later became\r\nthe cradle of more complex cultural developments. Stable resources, temperate climate and relatively easy\r\nmovements along the coastline has made the Pacific coast an even stronger candidate to explain early\r\nhuman dispersal and the construction of long-term cultural niche. In contrast, the Intermediate Depression\r\nin the hyperarid core of the Atacama Desert, between the Pacific coast and the Andes has not been\r\nperceived as a sufficiently productive enough ecosystem to support early human settling and dispersion.\r\nTheoretically, it has been assumed that it was used as an area of complementary resources for both\r\ncoastal and Andean hunter-gatherer societies. In this proposal, we expect to show that this traditional view\r\nis incorrect and propose that the Intermediate Depression was not just an area of complementary\r\nresources and a barrier for human dispersal. On the contrary, we aim to provide new data showing\r\nhow this region facilitated local settling and the expansion of H. sapiens into different\r\necosystems of South America, as it acted as an interglacial ecological refuge. Moreover, we\r\npropose that, despite an almost complete lack of rainfall, the Pampa del Tamarugal (PdT) was a much\r\nmore productive and complex ecosystem during the Pleistocene-Holocene transition than today. Well-dated\r\nearly residential areas, along with certain geomorphological and hydroclimatic features such as high watertable,\r\nmild temperatures and relatively warm winters generated extensive and diverse wetlands, creating\r\nsome enclaves of the PdT very attractive compared to other regions. One of our main goals is to find these\r\nplaces, and ecologically and culturally characterize them. Conversely, we will investigate the potential of\r\nthis basin as a glacial refuge a self-contained ecosystem that harbored many species of plants and animals\r\nthat today occur at higher elevations, and uniquely suited to sustain small populations of hunter-gatherers\r\nthat moved into the region, who then adopted and transformed this environment into their home. In this\r\ncontext, this proposal aims to research and understand how human societies developed long-term\r\nresidential systems in a former ecological refuge withing this hyperarid desert. By describing and\r\nanalyzing the dynamically productive environmental conditions of the PdT, we will address three major\r\nresearch problems: (a) the development of long-term residential systems, which gave rise to a\r\nconspicuous Intermediate Depression or pampa socio-ecological system, (b) the emergence of the PdT as a\r\nglacial refuge during the last glacial-interglacial transition; and (c) the coevolution and interdependence of\r\nthe natural and cultural systems that ended with the disappearance of the pampa socio-ecological system\r\nand concomitant sequential extinction and extirpation of its biodiversity. The corollary of this process was\r\nthat at the beginning of the Holocene, when the availability of water became insufficient, an exodus took\r\nplace that must have had profound consequences for these groups, who had to abandon this landscape\r\nthat they co-created for almost 2,000 years. Consequently, unlike the Andes or the Pacific coast, this early\r\nsocio-ecological system did not continue into the Holocene. The lack of high quality and publicly available\r\narchaeological, paleoecological and paleontological datasets has weakened the general theoretical debate\r\non early human migrations, settlement and the development of local socio-ecological systems. Here, we\r\nconceive human societies as part of the natural ecosystems on which they depend for their subsistence\r\nusing a socio-ecological approach to analyze and understand the relationship and mutual influence between\r\nhumans and what we consider nature today. This does not mean that early hunter-gatherers did not\r\nexploit or overexploit natural resources, but that they viewed them as social beings and heavily sanction\r\noverexploitation when it occurs or try to avoid it, for example through the implementation of taboos. Our\r\nproject proposes the novel hypothesis that the Intermediate Depression offered sufficient\r\nconditions and resources for the development of a residential system and a unique pampa\r\ncultural tradition. Our view contrasts with the idea that the settlement pattern of the terminal\r\nPleistocene hunter-gatherers would have been highly mobile and short-lived. The second novelty of this\r\nresearch is the composite methodology, that integrates different disciplinary methods such as: stable\r\nisotope analyses including Sr (to search for regional human mobility); paleogenomics to improve the\r\nresolution of morphological bone and plant taxa determination; geochronological dating, involving OSL and\r\nU\/Th techniques to expand our chronologies; and technomorphological characterization of lithic, bone,\r\nwooden and textile artifacts, through complete cha\u00eene op\u00e9ratoire methodology, pedological studies for soil\r\nhorizon description. In sum, our major goal is to understand a different migration route and settlement\r\nsystem for the early peopling of the western slope of the Andes, by defining and explaining the\r\ncharacteristics of the residential systems developed in the PdT during the Pleistocene-Holocene transition,\r\nand the local ecologies associated to them. Our data will contribute towards resolving an old problem: the\r\ncolonization of South America through the study of what is likely one of the best preserved and mostly\r\nunaltered sets of early American sites in all South America.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2025 - Febrero 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26906\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fluctuaciones glaciares del Cuaternario tard\u00edo en Chile central: bases para comprender el pasado, presente y futuro del clima\u0094.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26906\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26906\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Fluctuaciones glaciares del Cuaternario tard\u00edo en Chile central: bases para comprender el pasado, presente y futuro del clima\u0094.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Patrocinante<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2025 - Junio 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>ARIA (UK)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26929\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26929\" aria-expanded=\"false\" aria-controls=\"collapse-26929\">\n                                            MagTecSkin: Novel Tactile Sensitive Electronic Skin based on Magnetic Technology\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26929\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26929\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Tactile sensing capabilities are crucial for manual dexterity, yet remain beyond the reach of today\u0092s robots. While recently developed robotic skins can measure contact forces accurately, they cannot bend or stretch, and therefore they cannot cover complex robot parts, such as finger joints or deformable links. Lorenzo and team will develop an innovative skin based on magnetic technology that can measure 3D contact forces on multiple contact points, as well as bend and stretch. This will unlock full-cover articulated and soft robots, which will ultimately lead to vastly advanced robot dexterity in manufacturing, logistics, agriculture, healthcare, and beyond.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2025 - Marzo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Pacific hydro<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26383\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Monitoreo de Alsodes cantillanensis:Hacia una estrategia integral de conservaci\u00f3n\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26383\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26383\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"](Tesis con finamiento externo, concursado) Este estudio se centra en la rana de pecho espinoso de Cantillana (Alsodes\r\ncantillanensis), una especie microend\u00e9mica y en peligro, cuya distribuci\u00f3n se limita\r\nal cord\u00f3n monta\u00f1oso de Cantillana en la Regi\u00f3n de O'Higgins. La investigaci\u00f3n tiene\r\ncomo objetivo evaluar la presencia y actividad de esta especie en el Santuario de la\r\nNaturaleza Cerro Poqui mediante el uso de monitoreo bioac\u00fastico y mediciones de\r\ncalidad del agua.\r\nSe implementar\u00e1 un detector de frecuencias vocales para registrar las llamadas de\r\nA. cantillanensis, permitiendo identificar patrones de actividad y evaluar la relaci\u00f3n\r\nentre sus vocalizaciones y las condiciones ambientales. Adem\u00e1s, se analizar\u00e1 la\r\nposible presencia de la rana africana de u\u00f1as (Xenopus laevis), una especie invasora\r\nque podr\u00eda representar una amenaza al competir por recursos o actuar como vector\r\nde enfermedades.\r\nLos resultados esperados incluyen registros ac\u00fasticos de Alsodes cantillanensis,\r\nmediciones de calidad del agua en sus h\u00e1bitats y una evaluaci\u00f3n preliminar de la\r\ncoexistencia con Xenopus laevis. Esta informaci\u00f3n servir\u00e1 de base para futuras\r\nestrategias de conservaci\u00f3n y manejo, ayudando a mitigar los impactos de especies\r\ninvasoras en ecosistemas fr\u00e1giles.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26399\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Retos y soluciones sostenibles para fortalecer la cadena productiva del ma\u00edz en la regi\u00f3n centro-sur de Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26399\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26399\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El constante aumento de la poblaci\u00f3n humana exige una producci\u00f3n de alimentos que sea r\u00e1pida y sostenible. Debido a esto, los fertilizantes qu\u00edmicos se han utilizado extensamente, a menudo en exceso, lo que genera m\u00faltiples problemas. Esto hace que la sostenibilidad agr\u00edcola a mediano y largo plazo dependa de la implementaci\u00f3n de alternativas m\u00e1s accesibles y ecol\u00f3gicamente seguras. La productividad agr\u00edcola mundial se enfrenta a di&#64257;cultades debido a tensiones humanas, abi\u00f3ticas y ambientales causadas por el cambio clim\u00e1tico. Este proyecto busca resolver estos desaf\u00edos mediante el estudio de estrategias sostenibles para mejorar la e&#64257;ciencia en la producci\u00f3n de ma\u00edz en el centro-sur de Chile. El proyecto propone evaluar el impacto de estas estrategias en la absorci\u00f3n y removilizaci\u00f3n de nutrientes, la sanidad vegetal, as\u00ed como en el rendimiento y calidad del ma\u00edz. En Chile, el ma\u00edz desempe\u00f1a un papel vital en la agricultura, tanto en la alimentaci\u00f3n humana como animal. Se prev\u00e9 que los resultados de esta investigaci\u00f3n impulsen una producci\u00f3n de ma\u00edz m\u00e1s sostenible y resistente ante los retos ambientales y econ\u00f3micos actuales en la regi\u00f3n centro-sur de Chile.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26504\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Evaluaci\u00f3n de Educaci\u00f3n Financiera para J\u00f3venes de Educaci\u00f3n Terciaria\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26504\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26504\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Durante el 2023, todas y todos los j\u00f3venes de primer a\u00f1o del Centro de Formaci\u00f3n T\u00e9cnica INACAP debieron realizar obligatoriamente el curso \"Educaci\u00f3n Financiera para la ciudadan\u00eda\", iniciativa desarrollada por el proyecto Mi Barrio Financiero, desarrollado por la Facultad de Econom\u00eda y Negocios de la Universidad de Chile y la Asociaci\u00f3n Bancos. Mediante esta alianza con la CMF podremos evaluar el impacto en su comportamiento financiero, y lo compararemos con la generaci\u00f3n 2022.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26780\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Retos y soluciones sostenibles para fortalecer la cadena productiva del ma\u00edz en la regi\u00f3n centro-sur de Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26780\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26780\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El constante aumento de la poblaci\u00f3n humana exige una producci\u00f3n de alimentos que sea r\u00e1pida y sostenible. Debido a esto, los fertilizantes qu\u00edmicos se han utilizado extensamente, a menudo en exceso, lo que genera m\u00faltiples problemas. Esto hace que la sostenibilidad agr\u00edcola a mediano y largo plazo dependa de la implementaci\u00f3n de alternativas m\u00e1s accesibles y ecol\u00f3gicamente seguras. La productividad agr\u00edcola mundial se enfrenta a di&#64257;cultades debido a tensiones humanas, abi\u00f3ticas y ambientales causadas por el cambio clim\u00e1tico. Este proyecto busca resolver estos desaf\u00edos mediante el estudio de estrategias sostenibles para mejorar la e&#64257;ciencia en la producci\u00f3n de ma\u00edz en el centro-sur de Chile. El proyecto propone evaluar el impacto de estas estrategias en la absorci\u00f3n y removilizaci\u00f3n de nutrientes, la sanidad vegetal, as\u00ed como en el rendimiento y calidad del ma\u00edz. En Chile, el ma\u00edz desempe\u00f1a un papel vital en la agricultura, tanto en la alimentaci\u00f3n humana como animal. Se prev\u00e9 que los resultados de esta investigaci\u00f3n impulsen una producci\u00f3n de ma\u00edz m\u00e1s sostenible y resistente ante los retos ambientales y econ\u00f3micos actuales en la regi\u00f3n centro-sur de Chile.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2025 - Marzo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26046\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            FONDO DE INVESTIGACI\u00d3N PARA ESTUDIANTES DE PREGRADO\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26046\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26046\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El trabajo de la estudiante colaboradora (Catalina Vera Stewart, PEP - ESEd) consisti\u00f3 en una revisi\u00f3n de literatura en espa\u00f1ol acerca de la tem\u00e1tica de los espacios exteriores y la educaci\u00f3n inicial o de la primera infancia (en Chile, educaci\u00f3n \u0093parvularia\u0094). El an\u00e1lisis ha sido realizado como complemento al trabajo de revisi\u00f3n de literatura angl\u00f3fona y franc\u00f3fona efectuado por las investigadoras Catherine Bouve y Pascale Garnier, de la Universidad Sorbonne Paris Nord (Francia), en el marco del proyecto de investigaci\u00f3n \u0093La experiencia de ni\u00f1os y ni\u00f1as peque\u00f1os en espacios exteriores en centros de atenci\u00f3n a la primera infancia: Una exploraci\u00f3n socioetnogr\u00e1fica y geogr\u00e1fica, un enfoque comparativo entre Am\u00e9rica Latina y Europa\"[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2025 - Junio 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26356\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transformaci\u00f3n digital en Educaci\u00f3n Superior: Evaluaci\u00f3n de competencias digitales en estudiantes de la Universidad de O\u0092Higgins desde una perspectiva de g\u00e9nero\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26356\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26356\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto busca analizar el nivel de competencias digitales en estudiantes universitarios, abordando las brechas de g\u00e9nero como un aspecto clave para una educaci\u00f3n inclusiva y adaptada a las demandas de la era digital. La tem\u00e1tica seleccionada es orden de g\u00e9nero, ya que est\u00e1 investigaci\u00f3n evaluar\u00e1 los factores asociados a las competencias digitales en estudiantes de primer y \u00faltimo a\u00f1o de la Universidad de O\u0092Higgins, con el prop\u00f3sito de validar su impacto en la formaci\u00f3n acad\u00e9mica y el desarrollo de una ciudadan\u00eda digital activa y responsable.\r\nPara alcanzar este objetivo, se utilizar\u00e1 un modelo de ecuaciones estructurales (SEM) que permitir\u00e1 medir cinco dimensiones de competencias digitales seg\u00fan el Marco Europeo DigComp: alfabetizaci\u00f3n informacional y de datos, comunicaci\u00f3n y colaboraci\u00f3n, creaci\u00f3n de contenido digital, seguridad y resoluci\u00f3n de problemas. Adem\u00e1s, se evaluar\u00e1 el efecto moderador del g\u00e9nero en la relaci\u00f3n entre estas competencias y el nivel de ciudadan\u00eda digital, considerando su relevancia en el contexto de la transformaci\u00f3n digital.\r\nEl estudio se desarrollar\u00e1 mediante un enfoque cuantitativo, utilizando un cuestionario validado que ser\u00e1 aplicado a una muestra representativa de estudiantes con equidad de g\u00e9nero. Los resultados ser\u00e1n analizados a trav\u00e9s de SEM con m\u00ednimos cuadrados parciales (PLS-SEM) para entender c\u00f3mo estas competencias impactan la preparaci\u00f3n de los y las estudiantes frente a los desaf\u00edos digitales actuales. Al finalizar el proyecto, los resultados se compartir\u00e1n mediante, al menos, una publicaci\u00f3n cient\u00edfica de alto impacto, una presentaci\u00f3n en congreso, y un seminario de cierre dirigido a la comunidad universitaria, generando una base de conocimiento que apoye el desarrollo de pol\u00edticas institucionales para reducir las brechas digitales de g\u00e9nero en la educaci\u00f3n superior.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI240178<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2025 - Enero 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26396\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26396\" aria-expanded=\"false\" aria-controls=\"collapse-26396\">\n                                            Retos y soluciones sostenibles para fortalecer la cadena productiva del ma\u00edz en la regi\u00f3n centro-sur de Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26396\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26396\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El constante aumento de la poblaci\u00f3n humana exige una producci\u00f3n de alimentos que sea r\u00e1pida y sostenible. Debido a esto, los fertilizantes qu\u00edmicos se han utilizado extensamente, a menudo en exceso, lo que genera m\u00faltiples problemas. Esto hace que la sostenibilidad agr\u00edcola a mediano y largo plazo dependa de la implementaci\u00f3n de alternativas m\u00e1s accesibles y ecol\u00f3gicamente seguras. La productividad agr\u00edcola mundial se enfrenta a di&#64257;cultades debido a tensiones humanas, abi\u00f3ticas y ambientales causadas por el cambio clim\u00e1tico. Este proyecto busca resolver estos desaf\u00edos mediante el estudio de estrategias sostenibles para mejorar la e&#64257;ciencia en la producci\u00f3n de ma\u00edz en el centro-sur de Chile. El proyecto propone evaluar el impacto de estas estrategias en la absorci\u00f3n y removilizaci\u00f3n de nutrientes, la sanidad vegetal, as\u00ed como en el rendimiento y calidad del ma\u00edz. En Chile, el ma\u00edz desempe\u00f1a un papel vital en la agricultura, tanto en la alimentaci\u00f3n humana como animal. Se prev\u00e9 que los resultados de esta investigaci\u00f3n impulsen una producci\u00f3n de ma\u00edz m\u00e1s sostenible y resistente ante los retos ambientales y econ\u00f3micos actuales en la regi\u00f3n centro-sur de Chile.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI240153<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2025 - Junio 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26465\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26465\" aria-expanded=\"false\" aria-controls=\"collapse-26465\">\n                                            Territorios y Gobernanza del Riesgo: Fortaleciendo la Interdisciplina para prevenir Desastres Socio-naturales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26465\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26465\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La ocurrencia de desastres asociados a amenazas naturales representa un desaf\u00edo muy importante para Chile. Los frecuentes incendios en territorios forestales, los costos asociados a aluviones e inundaciones como las ocurridas en los inviernos de 2021 y de 2023 en la regi\u00f3n de O\u0092Higgins, e incluso la permanente amenaza de terremotos y volcanes, representan enormes costos para los territorios. Recientemente, la institucionalidad p\u00fablica ha avanzado en el desarrollo de pol\u00edticas de prevenci\u00f3n de desastres con la aprobaci\u00f3n de la Ley 21.364 (2021), creando el Sistema Nacional de Prevenci\u00f3n y Respuesta ante Desastres (SINAPRED), sustituyendo la Oficina Nacional de Emergencia (ONEMI) por el Servicio Nacional de Prevenci\u00f3n y Respuesta ante Desastres (SENAPRED). \r\nLa ciencia tiene mucho que aportar a esta nueva institucionalidad p\u00fablica. La Universidad de O\u0092Higgins (UOH), por ejemplo, colabora con SENAPRED O\u0092Higgins a trav\u00e9s de la Mesa de Peligros Geol\u00f3gicos, instaurada el a\u00f1o 2021. No obstante, el desaf\u00edo de la prevenci\u00f3n de desastres y el fomento de la resiliencia necesita otras perspectivas que consideren las caracter\u00edsticas de los espacios geogr\u00e1ficos donde se producen los riesgos. Se necesita un trabajo colaborativo con la institucionalidad p\u00fablica y la comunidad local, pero sobre todo, una perspectiva interdisciplinaria que a\u00fane los conocimientos de la ciencia social y natural. \r\nLa propuesta presentada busca generar una red que vincule a investigadores\/as nacionales (UOH y Universidad de Chile) con investigadores de universidades de Pa\u00edses Bajos (Universidad Libre de Amsterdam) y Dinamarca (Universidad de Copenhague), para realizar actividades de intercambio de experiencias e investigaci\u00f3n aplicada. Estos investigadores han logrado incidir en pol\u00edticas p\u00fablicas y estrategias a nivel local y regional en diversos pa\u00edses de Europa. Siguiendo una mirada multi-sectorial y nutridos de varias disciplinas, estos expertos han desarrollado perspectivas, herramientas y conocimientos de los cuales, sin duda, podemos aprender dada la coyuntura chilena con su nueva institucionalidad. \r\nEl proyecto contempla tres etapas para crear y potenciar esta red. Primero, el equipo nacional visitar \u00c1msterdam y Copenhague para vincularse con equipos interdisciplinarios, intercambiando experiencias de trabajo aplicado. Destaca el trabajo que realiza el equipo de Chile con SENAPRED O\u0092Higgins, y el trabajo aplicado en Europa con el Proyecto LINKS\r\n(https:\/\/links-project.eu\/). Segundo, un experto de Europa visitar\u00e1 la UOH. En esta visita, el invitado participar\u00e1 en reuniones y talleres, y colaborar\u00e1 con investigaci\u00f3n aplicada en la regi\u00f3n. Y tercero, el proyecto realizar\u00e1 una serie de eventos presenciales, como un seminario nacional con el experto internacional, adem\u00e1s de talleres aplicados con diferentes partes interesadas. A estos eventos se invitar\u00e1 a representantes de organismos p\u00fablicos, acad\u00e9micos\/as de otras instituciones y a la comunidad interesada en general. \r\nComo resultado, esta red permitir\u00e1: (1) intercambiar experiencias y difundir conocimiento aplicado sobre la gesti\u00f3n del riesgo a trav\u00e9s de perspectivas interdisciplinarias; (3) potenciar el capital humano de estudiantes de la UOH y promover la investigaci\u00f3n interdisciplinaria en la gesti\u00f3n del riesgo; y (3) crear y consolidar una entidad que visibilice el trabajo que realiza la UOH en torno a la gesti\u00f3n del riesgo, contribuyendo as\u00ed a la reducci\u00f3n del riesgo de desastres  a nivel regional y de la macrozona.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI240153<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2025 - Junio 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26514\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26514\" aria-expanded=\"false\" aria-controls=\"collapse-26514\">\n                                            Territorios y Gobernanza del Riesgo: Fortaleciendo la Interdisciplina para prevenir Desastres Socio-naturales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26514\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26514\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La ocurrencia de desastres asociados a amenazas naturales representa un desaf\u00edo muy importante para Chile. Los frecuentes incendios en territorios forestales, los costos asociados a aluviones e inundaciones como las ocurridas en los inviernos de 2021 y de 2023 en la regi\u00f3n de O\u0092Higgins, e incluso la permanente amenaza de terremotos y volcanes, representan enormes costos para los territorios. Recientemente, la institucionalidad p\u00fablica ha avanzado en el desarrollo de pol\u00edticas de prevenci\u00f3n de desastres con la aprobaci\u00f3n de la Ley 21.364 (2021), creando el Sistema Nacional de Prevenci\u00f3n y Respuesta ante Desastres (SINAPRED), sustituyendo la Oficina Nacional de Emergencia (ONEMI) por el Servicio Nacional de Prevenci\u00f3n y Respuesta ante Desastres (SENAPRED). \r\nLa ciencia tiene mucho que aportar a esta nueva institucionalidad p\u00fablica. La Universidad de O\u0092Higgins (UOH), por ejemplo, colabora con SENAPRED O\u0092Higgins a trav\u00e9s de la Mesa de Peligros Geol\u00f3gicos, instaurada el a\u00f1o 2021. No obstante, el desaf\u00edo de la prevenci\u00f3n de desastres y el fomento de la resiliencia necesita otras perspectivas que consideren las caracter\u00edsticas de los espacios geogr\u00e1ficos donde se producen los riesgos. Se necesita un trabajo colaborativo con la institucionalidad p\u00fablica y la comunidad local, pero sobre todo, una perspectiva interdisciplinaria que a\u00fane los conocimientos de la ciencia social y natural. \r\nLa propuesta presentada busca generar una red que vincule a investigadores\/as nacionales (UOH y Universidad de Chile) con investigadores de universidades de Pa\u00edses Bajos (Universidad Libre de Amsterdam) y Dinamarca (Universidad de Copenhague), para realizar actividades de intercambio de experiencias e investigaci\u00f3n aplicada. Estos investigadores han logrado incidir en pol\u00edticas p\u00fablicas y estrategias a nivel local y regional en diversos pa\u00edses de Europa. Siguiendo una mirada multi-sectorial y nutridos de varias disciplinas, estos expertos han desarrollado perspectivas, herramientas y conocimientos de los cuales, sin duda, podemos aprender dada la coyuntura chilena con su nueva institucionalidad. \r\nEl proyecto contempla tres etapas para crear y potenciar esta red. Primero, el equipo nacional visitar \u00c1msterdam y Copenhague para vincularse con equipos interdisciplinarios, intercambiando experiencias de trabajo aplicado. Destaca el trabajo que realiza el equipo de Chile con SENAPRED O\u0092Higgins, y el trabajo aplicado en Europa con el Proyecto LINKS\r\n(https:\/\/links-project.eu\/). Segundo, un experto de Europa visitar\u00e1 la UOH. En esta visita, el invitado participar\u00e1 en reuniones y talleres, y colaborar\u00e1 con investigaci\u00f3n aplicada en la regi\u00f3n. Y tercero, el proyecto realizar\u00e1 una serie de eventos presenciales, como un seminario nacional con el experto internacional, adem\u00e1s de talleres aplicados con diferentes partes interesadas. A estos eventos se invitar\u00e1 a representantes de organismos p\u00fablicos, acad\u00e9micos\/as de otras instituciones y a la comunidad interesada en general. \r\nComo resultado, esta red permitir\u00e1: (1) intercambiar experiencias y difundir conocimiento aplicado sobre la gesti\u00f3n del riesgo a trav\u00e9s de perspectivas interdisciplinarias; (3) potenciar el capital humano de estudiantes de la UOH y promover la investigaci\u00f3n interdisciplinaria en la gesti\u00f3n del riesgo; y (3) crear y consolidar una entidad que visibilice el trabajo que realiza la UOH en torno a la gesti\u00f3n del riesgo, contribuyendo as\u00ed a la reducci\u00f3n del riesgo de desastres  a nivel regional y de la macrozona.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2025 - Febrero 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26567\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26567\" aria-expanded=\"false\" aria-controls=\"collapse-26567\">\n                                            Fondo de investigaci\u00f3n para estudiantes de pregrado, III convocatoria verano 2025. Nilda Molina\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26567\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26567\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]A[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Patrocinante<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2025 - Febrero 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26568\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26568\" aria-expanded=\"false\" aria-controls=\"collapse-26568\">\n                                            Fondo de investigaci\u00f3n para estudiantes de pregrado, III convocatoria verano 2025. Marco P\u00e9rez\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26568\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26568\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]PINNs[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Patrocinante<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2025 - Diciembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Ciencia, Tecnolog\u00eda, Conocimiento e Innovaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26644\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            PAR Explora O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26644\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26644\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto busca fortalecer las competencias en Ciencia, Tecnolog\u00eda, Conocimiento e Innovaci\u00f3n (CTCI) en comunidades educativas. Este objetivo se enfoca en escuelas p\u00fablicas de alta vulnerabilidad, promoviendo la integraci\u00f3n y valorizaci\u00f3n de las iniciativas del Programa Explora, y robusteciendo el ecosistema CTCI en la regi\u00f3n de O'Higgins.\r\n\r\nObjetivo General:\r\nContribuir al fortalecimiento de competencias CTCI en comunidades educativas mediante la valorizaci\u00f3n y apropiaci\u00f3n de los instrumentos del Programa Explora, con especial \u00e9nfasis en establecimientos p\u00fablicos con altos \u00edndices de vulnerabilidad.\r\n\r\nObjetivos Espec\u00edficos:\r\n\r\nPlanificar, ejecutar y evaluar actividades que fortalezcan competencias CTCI en estudiantes, docentes y educadores de p\u00e1rvulos mediante la implementaci\u00f3n y evaluaci\u00f3n de instrumentos del Programa Explora.\r\nDise\u00f1ar e implementar un plan de acci\u00f3n para integrar las iniciativas del Programa Explora en la gesti\u00f3n educativa de las comunidades.\r\nEstablecer alianzas estrat\u00e9gicas con actores relevantes del sector p\u00fablico, privado y acad\u00e9mico para asegurar la sostenibilidad de las acciones del Programa Explora en colaboraci\u00f3n con el ecosistema CTCI.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2025 - Junio 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26645\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transformaci\u00f3n digital en Educaci\u00f3n Superior: Evaluaci\u00f3n de competencias digitales en estudiantes de la Universidad de O\u0092Higgins desde una perspectiva de g\u00e9nero\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26645\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26645\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto busca analizar el nivel de competencias digitales en estudiantes universitarios, abordando las brechas de g\u00e9nero como un aspecto clave para una educaci\u00f3n inclusiva y adaptada a las demandas de la era digital. La tem\u00e1tica seleccionada es orden de g\u00e9nero, ya que est\u00e1 investigaci\u00f3n evaluar\u00e1 los factores asociados a las competencias digitales en estudiantes de primer y \u00faltimo a\u00f1o de la Universidad de O\u0092Higgins, con el prop\u00f3sito de validar su impacto en la formaci\u00f3n acad\u00e9mica y el desarrollo de una ciudadan\u00eda digital activa y responsable.\r\nPara alcanzar este objetivo, se utilizar\u00e1 un modelo de ecuaciones estructurales (SEM) que permitir\u00e1 medir cinco dimensiones de competencias digitales seg\u00fan el Marco Europeo DigComp: alfabetizaci\u00f3n informacional y de datos, comunicaci\u00f3n y colaboraci\u00f3n, creaci\u00f3n de contenido digital, seguridad y resoluci\u00f3n de problemas. Adem\u00e1s, se evaluar\u00e1 el efecto moderador del g\u00e9nero en la relaci\u00f3n entre estas competencias y el nivel de ciudadan\u00eda digital, considerando su relevancia en el contexto de la transformaci\u00f3n digital.\r\nEl estudio se desarrollar\u00e1 mediante un enfoque cuantitativo, utilizando un cuestionario validado que ser\u00e1 aplicado a una muestra representativa de estudiantes con equidad de g\u00e9nero. Los resultados ser\u00e1n analizados a trav\u00e9s de SEM con m\u00ednimos cuadrados parciales (PLS-SEM) para entender c\u00f3mo estas competencias impactan la preparaci\u00f3n de los y las estudiantes frente a los desaf\u00edos digitales actuales. Al finalizar el proyecto, los resultados se compartir\u00e1n mediante, al menos, una publicaci\u00f3n cient\u00edfica de alto impacto, una presentaci\u00f3n en congreso, y un seminario de cierre dirigido a la comunidad universitaria, generando una base de conocimiento que apoye el desarrollo de pol\u00edticas institucionales para reducir las brechas digitales de g\u00e9nero en la educaci\u00f3n superior.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2025 - Diciembre 2029<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>DAAD (Alemania) Program \"Excellence in Higher Education for Development Cooperation - exceed\" for the period 2025-2029.<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26692\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            One Health \u0096 Training and Research Global Network (OH-TARGET) &#8211; 2nd. phase\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26692\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26692\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The One Health \u0096 Training and Research Global Network (OH-TARGET) aims to improve global health\r\nconditions through an integrated One Health approach, which recognizes the interconnectedness of human,\r\nanimal, and environmental health. This approach is crucial for addressing complex health challenges, as it\r\nfosters a comprehensive understanding and systemic collaborative effort across various sectors. Aligned with\r\nthe priorities of German development cooperation, OH-TARGET specifically addresses global pandemic\r\nresponse, climate protection, health and education, gender equality, and digitalization. Building on the\r\ninsights gained from the 2020-2024 Exceed funding period, OH-TARGET will focus on the consolidation and\r\nlong-term sustainability of its activities. The project will employ a holistic and participatory approach to\r\ndevelop context-specific solutions in education, training, and research. By fostering interdisciplinary\r\ncollaboration, OH-TARGET enhances research competence, promotes sustainable development, and\r\noptimizes the health of people, animals, and ecosystems. The One Health approach not only provides a\r\nframework for addressing immediate health challenges but also contributes to long-term resilience and\r\nsustainability in global health, ultimately aiming to create healthier communities worldwide.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI240153<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2025 - Junio 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26866\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26866\" aria-expanded=\"false\" aria-controls=\"collapse-26866\">\n                                            Territorios y Gobernanza del Riesgo: Fortaleciendo la Interdisciplina para prevenir Desastres Socio-naturales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26866\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26866\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La ocurrencia de desastres asociados a amenazas naturales representa un desaf\u00edo muy importante para Chile. Los frecuentes incendios en territorios forestales, los costos asociados a aluviones e inundaciones como las ocurridas en los inviernos de 2021 y de 2023 en la regi\u00f3n de O\u0092Higgins, e incluso la permanente amenaza de terremotos y volcanes, representan enormes costos para los territorios. Recientemente, la institucionalidad p\u00fablica ha avanzado en el desarrollo de pol\u00edticas de prevenci\u00f3n de desastres con la aprobaci\u00f3n de la Ley 21.364 (2021), creando el Sistema Nacional de Prevenci\u00f3n y Respuesta ante Desastres (SINAPRED), sustituyendo la Oficina Nacional de Emergencia (ONEMI) por el Servicio Nacional de Prevenci\u00f3n y Respuesta ante Desastres (SENAPRED). \r\nLa ciencia tiene mucho que aportar a esta nueva institucionalidad p\u00fablica. La Universidad de O\u0092Higgins (UOH), por ejemplo, colabora con SENAPRED O\u0092Higgins a trav\u00e9s de la Mesa de Peligros Geol\u00f3gicos, instaurada el a\u00f1o 2021. No obstante, el desaf\u00edo de la prevenci\u00f3n de desastres y el fomento de la resiliencia necesita otras perspectivas que consideren las caracter\u00edsticas de los espacios geogr\u00e1ficos donde se producen los riesgos. Se necesita un trabajo colaborativo con la institucionalidad p\u00fablica y la comunidad local, pero sobre todo, una perspectiva interdisciplinaria que a\u00fane los conocimientos de la ciencia social y natural. \r\nLa propuesta presentada busca generar una red que vincule a investigadores\/as nacionales (UOH y Universidad de Chile) con investigadores de universidades de Pa\u00edses Bajos (Universidad Libre de Amsterdam) y Dinamarca (Universidad de Copenhague), para realizar actividades de intercambio de experiencias e investigaci\u00f3n aplicada. Estos investigadores han logrado incidir en pol\u00edticas p\u00fablicas y estrategias a nivel local y regional en diversos pa\u00edses de Europa. Siguiendo una mirada multi-sectorial y nutridos de varias disciplinas, estos expertos han desarrollado perspectivas, herramientas y conocimientos de los cuales, sin duda, podemos aprender dada la coyuntura chilena con su nueva institucionalidad. \r\nEl proyecto contempla tres etapas para crear y potenciar esta red. Primero, el equipo nacional visitar \u00c1msterdam y Copenhague para vincularse con equipos interdisciplinarios, intercambiando experiencias de trabajo aplicado. Destaca el trabajo que realiza el equipo de Chile con SENAPRED O\u0092Higgins, y el trabajo aplicado en Europa con el Proyecto LINKS\r\n(https:\/\/links-project.eu\/). Segundo, un experto de Europa visitar\u00e1 la UOH. En esta visita, el invitado participar\u00e1 en reuniones y talleres, y colaborar\u00e1 con investigaci\u00f3n aplicada en la regi\u00f3n. Y tercero, el proyecto realizar\u00e1 una serie de eventos presenciales, como un seminario nacional con el experto internacional, adem\u00e1s de talleres aplicados con diferentes partes interesadas. A estos eventos se invitar\u00e1 a representantes de organismos p\u00fablicos, acad\u00e9micos\/as de otras instituciones y a la comunidad interesada en general. \r\nComo resultado, esta red permitir\u00e1: (1) intercambiar experiencias y difundir conocimiento aplicado sobre la gesti\u00f3n del riesgo a trav\u00e9s de perspectivas interdisciplinarias; (3) potenciar el capital humano de estudiantes de la UOH y promover la investigaci\u00f3n interdisciplinaria en la gesti\u00f3n del riesgo; y (3) crear y consolidar una entidad que visibilice el trabajo que realiza la UOH en torno a la gesti\u00f3n del riesgo, contribuyendo as\u00ed a la reducci\u00f3n del riesgo de desastres  a nivel regional y de la macrozona.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2025 - Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad Nacional Aut\u00f3noma de M\u00e9xico (UNAM)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26867\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Descifrando la vulcanolog\u00eda f\u00edsica del grupo de volcanes de Rinc\u00f3n de Parangueo, Valle de Santiago, Guanajuato (M\u00e9xico): implicaciones a futuros riesgos volc\u00e1nicos.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26867\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26867\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Descifrando la vulcanolog\u00eda f\u00edsica del grupo de volcanes de Rinc\u00f3n de Parangueo, Valle de Santiago, Guanajuato (M\u00e9xico): implicaciones a futuros riesgos volc\u00e1nicos. Convocatoria Institucional de Investigaci\u00f3n Cient\u00edfica 2025 (Universidad de Guanajuato -M\u00e9xico). PI: Pooja Vinod Kshirsagar (Departamento en Minas, Metalurgia y Geolog\u00eda, de la Divisi\u00f3n de Ingenier\u00edas. Guanajuato). Role Laura Becerril: colaboradora extranjera.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2025 - Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Servicio Nacional de Prevenci\u00f3n y Respuesta ante Desastres<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26868\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Plan de Reducci\u00f3n del Riesgo de la Municipalidad de Palmilla\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26868\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26868\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La elaboraci\u00f3n del Plan Comunal del Municipio de Palmilla para la Reducci\u00f3n del Riesgo de Desastres (PRRD) implica varias etapas que incluye identificar y evaluar amenazas y vulnerabilidades, definir estrategias de reducci\u00f3n de riesgos, planificar la ejecuci\u00f3n de medidas, asignar responsabilidades, establecer un sistema de alerta, dise\u00f1ar planes de emergencia y realizar simulacros de manera continua. Para que el plan sea efectivo, se est\u00e1 fomentando la participaci\u00f3n comunitaria y la colaboraci\u00f3n con actores p\u00fablicos y privados, asegurando que el plan sea un \"documento vivo\" que se actualiza peri\u00f3dicamente para adaptarse a los cambios.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> REDES 21991<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2025 - Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26869\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Sensibilizaci\u00f3n sobre Peligros Geol\u00f3gicos en la isla de Rapa Nui\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26869\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26869\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Sensibilizaci\u00f3n sobre Peligros Geol\u00f3gicos en la isla de Rapa Nui[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2025 - Junio 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26883\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transformaci\u00f3n digital en Educaci\u00f3n Superior: Evaluaci\u00f3n de competencias digitales en estudiantes de la Universidad de O\u0092Higgins desde una perspectiva de g\u00e9nero\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26883\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26883\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto busca analizar el nivel de competencias digitales en estudiantes universitarios, abordando las brechas de g\u00e9nero como un aspecto clave para una educaci\u00f3n inclusiva y adaptada a las demandas de la era digital. La tem\u00e1tica seleccionada es orden de g\u00e9nero, ya que est\u00e1 investigaci\u00f3n evaluar\u00e1 los factores asociados a las competencias digitales en estudiantes de primer y \u00faltimo a\u00f1o de la Universidad de O\u0092Higgins, con el prop\u00f3sito de validar su impacto en la formaci\u00f3n acad\u00e9mica y el desarrollo de una ciudadan\u00eda digital activa y responsable.\r\nPara alcanzar este objetivo, se utilizar\u00e1 un modelo de ecuaciones estructurales (SEM) que permitir\u00e1 medir cinco dimensiones de competencias digitales seg\u00fan el Marco Europeo DigComp: alfabetizaci\u00f3n informacional y de datos, comunicaci\u00f3n y colaboraci\u00f3n, creaci\u00f3n de contenido digital, seguridad y resoluci\u00f3n de problemas. Adem\u00e1s, se evaluar\u00e1 el efecto moderador del g\u00e9nero en la relaci\u00f3n entre estas competencias y el nivel de ciudadan\u00eda digital, considerando su relevancia en el contexto de la transformaci\u00f3n digital.\r\nEl estudio se desarrollar\u00e1 mediante un enfoque cuantitativo, utilizando un cuestionario validado que ser\u00e1 aplicado a una muestra representativa de estudiantes con equidad de g\u00e9nero. Los resultados ser\u00e1n analizados a trav\u00e9s de SEM con m\u00ednimos cuadrados parciales (PLS-SEM) para entender c\u00f3mo estas competencias impactan la preparaci\u00f3n de los y las estudiantes frente a los desaf\u00edos digitales actuales. Al finalizar el proyecto, los resultados se compartir\u00e1n mediante, al menos, una publicaci\u00f3n cient\u00edfica de alto impacto, una presentaci\u00f3n en congreso, y un seminario de cierre dirigido a la comunidad universitaria, generando una base de conocimiento que apoye el desarrollo de pol\u00edticas institucionales para reducir las brechas digitales de g\u00e9nero en la educaci\u00f3n superior.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI240238<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26979\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Red acad\u00e9mica internacional para el fortalecimiento de la formaci\u00f3n inicial y continua de profesores que ense\u00f1an matem\u00e1ticas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26979\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26979\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Esta propuesta tiene como objetivo general articular una red acad\u00e9mica nacional e internacional para el fortalecimiento de la investigaci\u00f3n, docencia y formaci\u00f3n de capital humano avanzado sobre la formaci\u00f3n inicial y continua de profesores\/as que ense\u00f1an matem\u00e1ticas en la educaci\u00f3n parvularia, b\u00e1sica y especial. Si bien diferentes comunidades han reportado que el conocimiento de las matem\u00e1ticas de los profesores es clave en el aprendizaje de los estudiantes, e incluso en la calidad de las clases que puedan ofrecer, la evidencia actual se\u00f1ala la necesidad de impulsar y potenciar la reactivaci\u00f3n de los aprendizajes matem\u00e1ticos para contrarrestar diversos fen\u00f3menos que han afectado el aprendizaje de ni\u00f1os y ni\u00f1as, tanto a nivel nacional como regional. Por tanto, esta propuesta busca atender al \u00e1rea estrat\u00e9gica de Educaci\u00f3n, un \u00e1rea prioritaria para la macrozona centro-sur en la cual se inserta la instituci\u00f3n beneficiaria: la Universidad de O\u0092Higgins (UOH).\r\nDe manera general, esta propuesta se interesa por el conocimiento del profesor y su desarrollo profesional. La instituci\u00f3n beneficiaria, la UOH, fue creada en el a\u00f1o 2015 con el objetivo de formar profesionales en y para la regi\u00f3n de O\u0092Higgins. A pesar de que actualmente la instituci\u00f3n est\u00e1 formando a m\u00e1s de 1.300 estudiantes que cursan carreras de pedagog\u00eda, el car\u00e1cter de universidad nueva requiere potenciar y enriquecer los programas de formaci\u00f3n docente en la regi\u00f3n. La red acad\u00e9mica formada por un grupo de investigadores\/as en educaci\u00f3n matem\u00e1tica para los niveles iniciales del sistema educativo (educaci\u00f3n parvularia, educaci\u00f3n b\u00e1sica y educaci\u00f3n especial) permitir\u00e1 establecer v\u00ednculos entre diferentes instituciones y acad\u00e9micos, as\u00ed como transferir las investigaciones cient\u00edficas a la pr\u00e1ctica educativa, fortaleciendo as\u00ed la formaci\u00f3n docente e impactando en el dise\u00f1o y desarrollo de pol\u00edticas p\u00fablicas docentes con \u00e9nfasis regional.\r\nPara abordar la propuesta se ha conformado un equipo nacional compuesto por investigadores asociados a la instituci\u00f3n beneficiaria (UOH) y un investigador perteneciente a una universidad nacional asociada de reconocido prestigio en la formaci\u00f3n de docentes: la Universidad Metropolitana de Ciencias de la Educaci\u00f3n. El equipo nacional trabajar\u00e1 conjuntamente con un grupo de investigadoras de reconocido prestigio en la investigaci\u00f3n, innovaci\u00f3n y desarrollo relacionado con la ense\u00f1anza y aprendizaje de las matem\u00e1ticas en los primeros niveles educativos. Dichas investigadoras provienen de instituciones espa\u00f1olas (Universidad de Granada y Universidad de M\u00e1laga) y de una universidad estadounidense (Tufts University). Esta red acad\u00e9mica nacional e internacional permitir\u00e1 abordar dos grandes \u00e1reas de inter\u00e9s: (a) el fortalecimiento de la investigaci\u00f3n; (b) el fortalecimiento de la docencia; y (c) el fortalecimiento de la formaci\u00f3n de capital humano avanzado.\r\nEl proyecto que aqu\u00ed se presenta establece dos modalidades de vinculaci\u00f3n que permiten conseguir los prop\u00f3sitos declarados. En primer lugar, la modalidad A favorecer\u00e1 el desarrollo de pasant\u00edas\/capacitaci\u00f3n de perfeccionamiento de corta duraci\u00f3n en el extranjero y la modalidad C, que favorecer\u00e1 la realizaci\u00f3n de talleres o seminarios bilaterales y\/o multilaterales con la\/s instituci\u00f3n\/es participantes. En cuanto a los resultados esperados, esta red fortalecer\u00e1 la investigaci\u00f3n colaborativa, promoviendo v\u00ednculos que permitan publicar recomendaciones y art\u00edculos cient\u00edficos que influyan en pol\u00edticas p\u00fablicas y cursos de desarrollo profesional. Adem\u00e1s, se busca mejorar la docencia mediante la transferencia de conocimientos y herramientas a docentes en formaci\u00f3n y en ejercicio, impactando en el aprendizaje de ni\u00f1os de 3 a 12 a\u00f1os. La formaci\u00f3n de capital humano avanzado se lograr\u00e1 mediante convenios de colaboraci\u00f3n, tesis conjuntas y talleres para estudiantes de posgrado, enriqueciendo sus capacidades profesionales y acad\u00e9micas. Pasant\u00edas de investigadores y estudiantes contribuir\u00e1n al desarrollo de estas \u00e1reas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI240178<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2025 - Enero 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27012\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27012\" aria-expanded=\"false\" aria-controls=\"collapse-27012\">\n                                            Retos y soluciones sostenibles para fortalecer la cadena productiva del ma\u00edz en la regi\u00f3n centro-sur de Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27012\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27012\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El constante aumento de la poblaci\u00f3n humana exige una producci\u00f3n de alimentos que sea r\u00e1pida y sostenible. Debido a esto, los fertilizantes qu\u00edmicos se han utilizado extensamente, a menudo en exceso, lo que genera m\u00faltiples problemas. Esto hace que la sostenibilidad agr\u00edcola a mediano y largo plazo dependa de la implementaci\u00f3n de alternativas m\u00e1s accesibles y ecol\u00f3gicamente seguras. La productividad agr\u00edcola mundial se enfrenta a di&#64257;cultades debido a tensiones humanas, abi\u00f3ticas y ambientales causadas por el cambio clim\u00e1tico. Este proyecto busca resolver estos desaf\u00edos mediante el estudio de estrategias sostenibles para mejorar la e&#64257;ciencia en la producci\u00f3n de ma\u00edz en el centro-sur de Chile. El proyecto propone evaluar el impacto de estas estrategias en la absorci\u00f3n y removilizaci\u00f3n de nutrientes, la sanidad vegetal, as\u00ed como en el rendimiento y calidad del ma\u00edz. En Chile, el ma\u00edz desempe\u00f1a un papel vital en la agricultura, tanto en la alimentaci\u00f3n humana como animal. Se prev\u00e9 que los resultados de esta investigaci\u00f3n impulsen una producci\u00f3n de ma\u00edz m\u00e1s sostenible y resistente ante los retos ambientales y econ\u00f3micos actuales en la regi\u00f3n centro-sur de Chile.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI240153<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2025 - Junio 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27028\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27028\" aria-expanded=\"false\" aria-controls=\"collapse-27028\">\n                                            Territorios y Gobernanza del Riesgo: Fortaleciendo la Interdisciplina para prevenir Desastres Socio-naturales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27028\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27028\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La ocurrencia de desastres asociados a amenazas naturales representa un desaf\u00edo muy importante para Chile. Los frecuentes incendios en territorios forestales, los costos asociados a aluviones e inundaciones como las ocurridas en los inviernos de 2021 y de 2023 en la regi\u00f3n de O\u0092Higgins, e incluso la permanente amenaza de terremotos y volcanes, representan enormes costos para los territorios. Recientemente, la institucionalidad p\u00fablica ha avanzado en el desarrollo de pol\u00edticas de prevenci\u00f3n de desastres con la aprobaci\u00f3n de la Ley 21.364 (2021), creando el Sistema Nacional de Prevenci\u00f3n y Respuesta ante Desastres (SINAPRED), sustituyendo la Oficina Nacional de Emergencia (ONEMI) por el Servicio Nacional de Prevenci\u00f3n y Respuesta ante Desastres (SENAPRED). \r\nLa ciencia tiene mucho que aportar a esta nueva institucionalidad p\u00fablica. La Universidad de O\u0092Higgins (UOH), por ejemplo, colabora con SENAPRED O\u0092Higgins a trav\u00e9s de la Mesa de Peligros Geol\u00f3gicos, instaurada el a\u00f1o 2021. No obstante, el desaf\u00edo de la prevenci\u00f3n de desastres y el fomento de la resiliencia necesita otras perspectivas que consideren las caracter\u00edsticas de los espacios geogr\u00e1ficos donde se producen los riesgos. Se necesita un trabajo colaborativo con la institucionalidad p\u00fablica y la comunidad local, pero sobre todo, una perspectiva interdisciplinaria que a\u00fane los conocimientos de la ciencia social y natural. \r\nLa propuesta presentada busca generar una red que vincule a investigadores\/as nacionales (UOH y Universidad de Chile) con investigadores de universidades de Pa\u00edses Bajos (Universidad Libre de Amsterdam) y Dinamarca (Universidad de Copenhague), para realizar actividades de intercambio de experiencias e investigaci\u00f3n aplicada. Estos investigadores han logrado incidir en pol\u00edticas p\u00fablicas y estrategias a nivel local y regional en diversos pa\u00edses de Europa. Siguiendo una mirada multi-sectorial y nutridos de varias disciplinas, estos expertos han desarrollado perspectivas, herramientas y conocimientos de los cuales, sin duda, podemos aprender dada la coyuntura chilena con su nueva institucionalidad. \r\nEl proyecto contempla tres etapas para crear y potenciar esta red. Primero, el equipo nacional visitar \u00c1msterdam y Copenhague para vincularse con equipos interdisciplinarios, intercambiando experiencias de trabajo aplicado. Destaca el trabajo que realiza el equipo de Chile con SENAPRED O\u0092Higgins, y el trabajo aplicado en Europa con el Proyecto LINKS\r\n(https:\/\/links-project.eu\/). Segundo, un experto de Europa visitar\u00e1 la UOH. En esta visita, el invitado participar\u00e1 en reuniones y talleres, y colaborar\u00e1 con investigaci\u00f3n aplicada en la regi\u00f3n. Y tercero, el proyecto realizar\u00e1 una serie de eventos presenciales, como un seminario nacional con el experto internacional, adem\u00e1s de talleres aplicados con diferentes partes interesadas. A estos eventos se invitar\u00e1 a representantes de organismos p\u00fablicos, acad\u00e9micos\/as de otras instituciones y a la comunidad interesada en general. \r\nComo resultado, esta red permitir\u00e1: (1) intercambiar experiencias y difundir conocimiento aplicado sobre la gesti\u00f3n del riesgo a trav\u00e9s de perspectivas interdisciplinarias; (3) potenciar el capital humano de estudiantes de la UOH y promover la investigaci\u00f3n interdisciplinaria en la gesti\u00f3n del riesgo; y (3) crear y consolidar una entidad que visibilice el trabajo que realiza la UOH en torno a la gesti\u00f3n del riesgo, contribuyendo as\u00ed a la reducci\u00f3n del riesgo de desastres  a nivel regional y de la macrozona.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> Proyecto URO 21991<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2025 - Marzo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27079\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Concurso de antecedentes de Agosto 2024 para optar a posiciones de Investigador\/a Postdoctoral en la Universidad de O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27079\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27079\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Implementaci\u00f3n de la investigaci\u00f3n 'Uso de inteligencia artificial para la exploraci\u00f3n de las bases neuroanat\u00f3micas del deterioro del insight en la enfermedad de Alzheimer' desde el cargo de Investigador Postdoctoral del Instituto de Ciencias de la Ingenier\u00eda de la Universidad de O\u0092Higgins.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2024 - Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26102\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Artificial Intelligence and Robotics for Remote and Proximal Sensing in Precision Agriculture\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26102\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26102\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]M\u00e9todos basados en representaciones neuronales impl\u00edcitas est\u00e1n empezando a usarse ampliamente en distintos \u00e1mbitos de visi\u00f3n computacional, rob\u00f3tica y sensado remoto. Este tipo de representaciones est\u00e1n permitiendo abordar m\u00faltiples problemas en ambientes no controlados como la agricultura, de manera robusta. Por ejemplo, m\u00e9todos basados en Neural Radiance Fields (NeRF) se est\u00e1n explorando de manera amplia tanto con im\u00e1genes satelitales como en problemas de rob\u00f3tica de campo. En este contexto, el proyecto busca aunar competencias en visi\u00f3n computacional y aprendizaje de m\u00e1quinas, usadas en la detecci\u00f3n remota y en rob\u00f3tica, para abordar nuevas t\u00e9cnicas basadas en representaciones neuronales impl\u00edcitas, para aplicaciones de la agricultura de precisi\u00f3n. Para lograr este objetivo, los investigadores convocados tienen un profundo conocimiento en estas \u00e1reas complementarias.\r\nEs importante destacar que las \u00e1reas de sensado remoto (satelital y drones) y sensado pr\u00f3ximo (robots y redes de sensores) est\u00e1n experimentando una aceleraci\u00f3n sin precedentes. En el caso de sensado remoto, adem\u00e1s de los grandes programas p\u00fablicos como Sentinel, los actores privados est\u00e1n creando flotas de microsat\u00e9lites capaces de vigilar la Tierra con revisitas diarias. Estos datos abundantes, baratos y de alta resoluci\u00f3n est\u00e1n creando oportunidades para desarrollar aplicaciones novedosas para la supervisi\u00f3n de la actividad agr\u00edcola. En el caso del sensado pr\u00f3ximo, las redes de sensores, junto con el uso de robots para monitoreo, est\u00e1 permitiendo un seguimiento regular de los procesos agr\u00edcolas, con una alta resoluci\u00f3n temporal y espacial, por lo que cada vez hay una mayor disponibilidad de datos, que complementan los datos obtenidos mediante sensado remoto.\r\nA nivel de uso, estas tecnolog\u00edas se complementan, y a nivel de investigaci\u00f3n, las t\u00e9cnicas utilizadas est\u00e1n empezando a converger, mediante el uso de m\u00e9todos basados en redes neuronales, y m\u00e1s espec\u00edficamente por m\u00e9todos basados en representaciones neuronales impl\u00edcitas, tales como Neural Radiance Fields (NeRF). Por todo esto, el estudio del sensado remoto y pr\u00f3ximo de manera conjunta, y mediante marcos de trabajo con t\u00e9cnicas similares como las representaciones neuronales impl\u00edcitas, tiene un gran potencial para en un futuro pr\u00f3ximo generar una visi\u00f3n integrada de los procesos agr\u00edcolas mejorando la sostenibilidad y eficiencia en la agricultura.\r\nDurante su ejecuci\u00f3n, el proyecto llevar\u00e1 a cabo actividades de investigaci\u00f3n conjunta, incluyendo seminarios online regulares, la toma de datos en terreno, y un workshop de cierre en el contexto de una conferencia internacional, que junto con el intercambio de investigadores en formaci\u00f3n (mag\u00edster, doctorado y\/o postdoctorado), as\u00ed como visitas de investigadores senior, buscan articular una de red de trabajo que aborde de manera interdisciplinar y con t\u00e9cnicas modernas, problem\u00e1ticas de sensado remoto y pr\u00f3ximo en agricultura de precisi\u00f3n mediante representaciones neuronales impl\u00edcitas, tales como Neural Radiance Fields (NeRF), entre otras.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FONDO DE INVESTIGACI\u00d3N INTERDISCIPLINARIA<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2024 - Diciembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26104\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Construcci\u00f3n de modelos de desarrollo y madurez de cerezas mediante IA y visi\u00f3n computacional 3D a partir de im\u00e1genes hiperespectrales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26104\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26104\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto busca aunar competencias en visi\u00f3n computacional y fruticultura, para habilitar la construcci\u00f3n de modelos de crecimiento y madurez de cerezas a partir de modelos 3D construidos a partir de im\u00e1genes hiperespectrales. En particular se desarrollar\u00e1n algoritmos de visi\u00f3n computacional 3D basados en representaciones neuronales impl\u00edcitas para estimar el color y tama\u00f1o de frutos en cerezo durante el ciclo de crecimiento y cosecha, as\u00ed como para estimar y correlacionar informaci\u00f3n hiperespectral con variables de calidad, como firmeza y grados brix de los frutos. A partir de estos algoritmos, se desarrollar\u00e1 una metodolog\u00eda para la construcci\u00f3n de modelos de crecimiento de los frutos que aporten a mejorar la calidad de la fruta fresca de exportaci\u00f3n.\r\nEs importante destacar que m\u00e9todos de machine learning basados en representaciones neuronales impl\u00edcitas est\u00e1n empezando a usarse ampliamente en distintos \u00e1mbitos de visi\u00f3n computacional, rob\u00f3tica y sensado remoto. Este tipo de representaciones est\u00e1 permitiendo abordar m\u00faltiples problemas en ambientes no controlados en la agricultura, de manera robusta. Por ejemplo, m\u00e9todos basados en redes neuronales impl\u00edcitas, tales como Neural Radiance Fields (NeRF) y Deep Signed Functions (DeepSDF) se est\u00e1n explorando para aplicaciones tales como reconstrucci\u00f3n 3D de frutas, \u00e1rboles y huertos, habilitando aplicaciones de agricultura de precisi\u00f3n, como conteo de frutas y an\u00e1lisis fenol\u00f3gico. Para que el desarrollo de estas aplicaciones tenga un impacto en la agricultura, es necesario el desarrollo de modelos desde una mirada interdisciplinar, considerando tanto m\u00e9todos del estado del arte de visi\u00f3n computacional y machine learning, as\u00ed como un conocimiento profundo de fruticultura y en particular de fisiolog\u00eda de los \u00e1rboles frutales caducos.\r\nLa calidad de la fruta de exportaci\u00f3n es un pilar fundamental de nuestra fruticultura, y desde esa base, se considera importante el desarrollo de herramientas de monitoreo y diagn\u00f3stico que permitan predecir calidad y condici\u00f3n de la fruta oportunamente, y sobre todo bajo un escenario de cambio clim\u00e1tico. En la temporada 2021-2022, un 20% de las cerezas presentaron serios problemas de calidad en los mercados de destino. De este volumen, un 28-47% se relacionaron con problemas de manejo en precosecha. En la agricultura convencional el uso de datos ha sido limitado a conocer procesos productivos puntuales tales como el monitoreo de variables ambientales o fisiol\u00f3gicas, las que han dado cuenta de un cierto estado del sistema de la planta de manera indirecta. Algunos avances en automatizaci\u00f3n en la toma de datos se han reportado para la aplicaci\u00f3n de riego de precisi\u00f3n. Sin embargo, desde el mundo acad\u00e9mico no existe un gran aprovechamiento de los avances en inteligencia artificial para la agronom\u00eda. En efecto, la predicci\u00f3n del comportamiento de variables productivas complejas, especialmente aquellas ligadas a la calidad de la fruta representan a\u00fan un desaf\u00edo no resuelto en la industria nacional. En este sentido las t\u00e9cnicas de machine learning han sido utilizadas con \u00e9xito para predecir el rendimiento en diversas especies agr\u00edcolas, incluyendo frutales. No obstante, la calidad de fruta ha sido escasamente abordada, pese a existir capacidades te\u00f3ricas. Debido a esto surge la necesidad del desarrollo de herramientas para construir modelos de crecimiento y madurez de cerezas, as\u00ed como para que los productores puedan hacer seguimiento de su producci\u00f3n, y en particular de la calidad de \u00e9sta.\r\nCon el objetivo de desarrollar una metodolog\u00eda para la construcci\u00f3n de modelos de desarrollo de cerezas mediante im\u00e1genes hiperespectral y modelos computacionales 3D de frutos, y as\u00ed aportar a la mejora de la calidad de la producci\u00f3n de la cereza, el proyecto propone abordar tres grandes objetivos:\r\n&#9679; Dise\u00f1ar y capturar base de datos de im\u00e1genes, de variables agroclim\u00e1ticas y mediciones fisiol\u00f3gicas.\r\n&#9679; Desarrollar m\u00e9todos de visi\u00f3n computacional y IA para la estimaci\u00f3n de calibre, firmeza, color, y\r\ngrados brix de cerezas.\r\n&#9679; Desarrollar, calibrar y validar modelos de crecimiento de cerezas a partir de los resultados obtenidos\r\ncon los algoritmos de visi\u00f3n computacional y IA desarrollados.\r\nPara alcanzar estos objetivos, los investigadores convocados tienen un profundo conocimiento en las \u00e1reas complementarias desde la ingenier\u00eda (visi\u00f3n computacional, machine learning y rob\u00f3tica), y la fruticultura (fisiolog\u00eda de los \u00e1rboles frutales caducos, sistemas de conducci\u00f3n, portainjertos, y gesti\u00f3n de huertos).[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2024 - Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26355\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Artificial Intelligence and Robotics for Remote and Proximal Sensing in Precision Agriculture\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26355\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26355\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]M\u00e9todos basados en representaciones neuronales impl\u00edcitas est\u00e1n empezando a usarse ampliamente en distintos \u00e1mbitos de visi\u00f3n computacional, rob\u00f3tica y sensado remoto. Este tipo de representaciones est\u00e1n permitiendo abordar m\u00faltiples problemas en ambientes no controlados como la agricultura, de manera robusta. Por ejemplo, m\u00e9todos basados en Neural Radiance Fields (NeRF) se est\u00e1n explorando de manera amplia tanto con im\u00e1genes satelitales como en problemas de rob\u00f3tica de campo. En este contexto, el proyecto busca aunar competencias en visi\u00f3n computacional y aprendizaje de m\u00e1quinas, usadas en la detecci\u00f3n remota y en rob\u00f3tica, para abordar nuevas t\u00e9cnicas basadas en representaciones neuronales impl\u00edcitas, para aplicaciones de la agricultura de precisi\u00f3n. Para lograr este objetivo, los investigadores convocados tienen un profundo conocimiento en estas \u00e1reas complementarias.\r\nEs importante destacar que las \u00e1reas de sensado remoto (satelital y drones) y sensado pr\u00f3ximo (robots y redes de sensores) est\u00e1n experimentando una aceleraci\u00f3n sin precedentes. En el caso de sensado remoto, adem\u00e1s de los grandes programas p\u00fablicos como Sentinel, los actores privados est\u00e1n creando flotas de microsat\u00e9lites capaces de vigilar la Tierra con revisitas diarias. Estos datos abundantes, baratos y de alta resoluci\u00f3n est\u00e1n creando oportunidades para desarrollar aplicaciones novedosas para la supervisi\u00f3n de la actividad agr\u00edcola. En el caso del sensado pr\u00f3ximo, las redes de sensores, junto con el uso de robots para monitoreo, est\u00e1 permitiendo un seguimiento regular de los procesos agr\u00edcolas, con una alta resoluci\u00f3n temporal y espacial, por lo que cada vez hay una mayor disponibilidad de datos, que complementan los datos obtenidos mediante sensado remoto.\r\nA nivel de uso, estas tecnolog\u00edas se complementan, y a nivel de investigaci\u00f3n, las t\u00e9cnicas utilizadas est\u00e1n empezando a converger, mediante el uso de m\u00e9todos basados en redes neuronales, y m\u00e1s espec\u00edficamente por m\u00e9todos basados en representaciones neuronales impl\u00edcitas, tales como Neural Radiance Fields (NeRF). Por todo esto, el estudio del sensado remoto y pr\u00f3ximo de manera conjunta, y mediante marcos de trabajo con t\u00e9cnicas similares como las representaciones neuronales impl\u00edcitas, tiene un gran potencial para en un futuro pr\u00f3ximo generar una visi\u00f3n integrada de los procesos agr\u00edcolas mejorando la sostenibilidad y eficiencia en la agricultura.\r\nDurante su ejecuci\u00f3n, el proyecto llevar\u00e1 a cabo actividades de investigaci\u00f3n conjunta, incluyendo seminarios online regulares, la toma de datos en terreno, y un workshop de cierre en el contexto de una conferencia internacional, que junto con el intercambio de investigadores en formaci\u00f3n (mag\u00edster, doctorado y\/o postdoctorado), as\u00ed como visitas de investigadores senior, buscan articular una de red de trabajo que aborde de manera interdisciplinar y con t\u00e9cnicas modernas, problem\u00e1ticas de sensado remoto y pr\u00f3ximo en agricultura de precisi\u00f3n mediante representaciones neuronales impl\u00edcitas, tales como Neural Radiance Fields (NeRF), entre otras.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FONDO DE INVESTIGACI\u00d3N INTERDISCIPLINARIA<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2024 - Diciembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26357\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Construcci\u00f3n de modelos de desarrollo y madurez de cerezas mediante IA y visi\u00f3n computacional 3D a partir de im\u00e1genes hiperespectrales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26357\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26357\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto busca aunar competencias en visi\u00f3n computacional y fruticultura, para habilitar la construcci\u00f3n de modelos de crecimiento y madurez de cerezas a partir de modelos 3D construidos a partir de im\u00e1genes hiperespectrales. En particular se desarrollar\u00e1n algoritmos de visi\u00f3n computacional 3D basados en representaciones neuronales impl\u00edcitas para estimar el color y tama\u00f1o de frutos en cerezo durante el ciclo de crecimiento y cosecha, as\u00ed como para estimar y correlacionar informaci\u00f3n hiperespectral con variables de calidad, como firmeza y grados brix de los frutos. A partir de estos algoritmos, se desarrollar\u00e1 una metodolog\u00eda para la construcci\u00f3n de modelos de crecimiento de los frutos que aporten a mejorar la calidad de la fruta fresca de exportaci\u00f3n.\r\nEs importante destacar que m\u00e9todos de machine learning basados en representaciones neuronales impl\u00edcitas est\u00e1n empezando a usarse ampliamente en distintos \u00e1mbitos de visi\u00f3n computacional, rob\u00f3tica y sensado remoto. Este tipo de representaciones est\u00e1 permitiendo abordar m\u00faltiples problemas en ambientes no controlados en la agricultura, de manera robusta. Por ejemplo, m\u00e9todos basados en redes neuronales impl\u00edcitas, tales como Neural Radiance Fields (NeRF) y Deep Signed Functions (DeepSDF) se est\u00e1n explorando para aplicaciones tales como reconstrucci\u00f3n 3D de frutas, \u00e1rboles y huertos, habilitando aplicaciones de agricultura de precisi\u00f3n, como conteo de frutas y an\u00e1lisis fenol\u00f3gico. Para que el desarrollo de estas aplicaciones tenga un impacto en la agricultura, es necesario el desarrollo de modelos desde una mirada interdisciplinar, considerando tanto m\u00e9todos del estado del arte de visi\u00f3n computacional y machine learning, as\u00ed como un conocimiento profundo de fruticultura y en particular de fisiolog\u00eda de los \u00e1rboles frutales caducos.\r\nLa calidad de la fruta de exportaci\u00f3n es un pilar fundamental de nuestra fruticultura, y desde esa base, se considera importante el desarrollo de herramientas de monitoreo y diagn\u00f3stico que permitan predecir calidad y condici\u00f3n de la fruta oportunamente, y sobre todo bajo un escenario de cambio clim\u00e1tico. En la temporada 2021-2022, un 20% de las cerezas presentaron serios problemas de calidad en los mercados de destino. De este volumen, un 28-47% se relacionaron con problemas de manejo en precosecha. En la agricultura convencional el uso de datos ha sido limitado a conocer procesos productivos puntuales tales como el monitoreo de variables ambientales o fisiol\u00f3gicas, las que han dado cuenta de un cierto estado del sistema de la planta de manera indirecta. Algunos avances en automatizaci\u00f3n en la toma de datos se han reportado para la aplicaci\u00f3n de riego de precisi\u00f3n. Sin embargo, desde el mundo acad\u00e9mico no existe un gran aprovechamiento de los avances en inteligencia artificial para la agronom\u00eda. En efecto, la predicci\u00f3n del comportamiento de variables productivas complejas, especialmente aquellas ligadas a la calidad de la fruta representan a\u00fan un desaf\u00edo no resuelto en la industria nacional. En este sentido las t\u00e9cnicas de machine learning han sido utilizadas con \u00e9xito para predecir el rendimiento en diversas especies agr\u00edcolas, incluyendo frutales. No obstante, la calidad de fruta ha sido escasamente abordada, pese a existir capacidades te\u00f3ricas. Debido a esto surge la necesidad del desarrollo de herramientas para construir modelos de crecimiento y madurez de cerezas, as\u00ed como para que los productores puedan hacer seguimiento de su producci\u00f3n, y en particular de la calidad de \u00e9sta.\r\nCon el objetivo de desarrollar una metodolog\u00eda para la construcci\u00f3n de modelos de desarrollo de cerezas mediante im\u00e1genes hiperespectral y modelos computacionales 3D de frutos, y as\u00ed aportar a la mejora de la calidad de la producci\u00f3n de la cereza, el proyecto propone abordar tres grandes objetivos:\r\n&#9679; Dise\u00f1ar y capturar base de datos de im\u00e1genes, de variables agroclim\u00e1ticas y mediciones fisiol\u00f3gicas.\r\n&#9679; Desarrollar m\u00e9todos de visi\u00f3n computacional y IA para la estimaci\u00f3n de calibre, firmeza, color, y\r\ngrados brix de cerezas.\r\n&#9679; Desarrollar, calibrar y validar modelos de crecimiento de cerezas a partir de los resultados obtenidos\r\ncon los algoritmos de visi\u00f3n computacional y IA desarrollados.\r\nPara alcanzar estos objetivos, los investigadores convocados tienen un profundo conocimiento en las \u00e1reas complementarias desde la ingenier\u00eda (visi\u00f3n computacional, machine learning y rob\u00f3tica), y la fruticultura (fisiolog\u00eda de los \u00e1rboles frutales caducos, sistemas de conducci\u00f3n, portainjertos, y gesti\u00f3n de huertos).[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2024 - Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26882\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Artificial Intelligence and Robotics for Remote and Proximal Sensing in Precision Agriculture\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26882\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26882\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]M\u00e9todos basados en representaciones neuronales impl\u00edcitas est\u00e1n empezando a usarse ampliamente en distintos \u00e1mbitos de visi\u00f3n computacional, rob\u00f3tica y sensado remoto. Este tipo de representaciones est\u00e1n permitiendo abordar m\u00faltiples problemas en ambientes no controlados como la agricultura, de manera robusta. Por ejemplo, m\u00e9todos basados en Neural Radiance Fields (NeRF) se est\u00e1n explorando de manera amplia tanto con im\u00e1genes satelitales como en problemas de rob\u00f3tica de campo. En este contexto, el proyecto busca aunar competencias en visi\u00f3n computacional y aprendizaje de m\u00e1quinas, usadas en la detecci\u00f3n remota y en rob\u00f3tica, para abordar nuevas t\u00e9cnicas basadas en representaciones neuronales impl\u00edcitas, para aplicaciones de la agricultura de precisi\u00f3n. Para lograr este objetivo, los investigadores convocados tienen un profundo conocimiento en estas \u00e1reas complementarias.\r\nEs importante destacar que las \u00e1reas de sensado remoto (satelital y drones) y sensado pr\u00f3ximo (robots y redes de sensores) est\u00e1n experimentando una aceleraci\u00f3n sin precedentes. En el caso de sensado remoto, adem\u00e1s de los grandes programas p\u00fablicos como Sentinel, los actores privados est\u00e1n creando flotas de microsat\u00e9lites capaces de vigilar la Tierra con revisitas diarias. Estos datos abundantes, baratos y de alta resoluci\u00f3n est\u00e1n creando oportunidades para desarrollar aplicaciones novedosas para la supervisi\u00f3n de la actividad agr\u00edcola. En el caso del sensado pr\u00f3ximo, las redes de sensores, junto con el uso de robots para monitoreo, est\u00e1 permitiendo un seguimiento regular de los procesos agr\u00edcolas, con una alta resoluci\u00f3n temporal y espacial, por lo que cada vez hay una mayor disponibilidad de datos, que complementan los datos obtenidos mediante sensado remoto.\r\nA nivel de uso, estas tecnolog\u00edas se complementan, y a nivel de investigaci\u00f3n, las t\u00e9cnicas utilizadas est\u00e1n empezando a converger, mediante el uso de m\u00e9todos basados en redes neuronales, y m\u00e1s espec\u00edficamente por m\u00e9todos basados en representaciones neuronales impl\u00edcitas, tales como Neural Radiance Fields (NeRF). Por todo esto, el estudio del sensado remoto y pr\u00f3ximo de manera conjunta, y mediante marcos de trabajo con t\u00e9cnicas similares como las representaciones neuronales impl\u00edcitas, tiene un gran potencial para en un futuro pr\u00f3ximo generar una visi\u00f3n integrada de los procesos agr\u00edcolas mejorando la sostenibilidad y eficiencia en la agricultura.\r\nDurante su ejecuci\u00f3n, el proyecto llevar\u00e1 a cabo actividades de investigaci\u00f3n conjunta, incluyendo seminarios online regulares, la toma de datos en terreno, y un workshop de cierre en el contexto de una conferencia internacional, que junto con el intercambio de investigadores en formaci\u00f3n (mag\u00edster, doctorado y\/o postdoctorado), as\u00ed como visitas de investigadores senior, buscan articular una de red de trabajo que aborde de manera interdisciplinar y con t\u00e9cnicas modernas, problem\u00e1ticas de sensado remoto y pr\u00f3ximo en agricultura de precisi\u00f3n mediante representaciones neuronales impl\u00edcitas, tales como Neural Radiance Fields (NeRF), entre otras.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2024 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26097\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26097\" aria-expanded=\"false\" aria-controls=\"collapse-26097\">\n                                            AIJ support grant for organizing the Third Latin American Summer School on Cognitive Robotics\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26097\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26097\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Fondos para apoyar la realizacion de la Third Latin American Summer School on Cognitive Robotics (LACORO 2024). La primera edici\u00f3n se realiz\u00f3 online en octubre de 2020; la segunda fue presencial en enero de 2023; la tercera versi\u00f3n tendr\u00e1 lugar entre el 9 y el 13 de diciembre de 2024 en la Universidad de O'Higgins en Rancagua, Chile. https:\/\/lacoro.org\/\r\n\r\nEsta Escuela de Verano beneficiar\u00e1 principalmente a Estudiantes y Acad\u00e9micos de las Am\u00e9ricas interesados en la Investigaci\u00f3n en Inteligencia Artificial aplicada a la Rob\u00f3tica. Nuestro objetivo es fomentar la colaboraci\u00f3n nacional y regional en esta \u00e1rea de investigaci\u00f3n. Para la primera edici\u00f3n, alcanzamos 241 inscripciones para actividades online de todo el mundo, y la segunda versi\u00f3n tuvo 166 inscripciones para actividades presenciales en enero de 2023, principalmente de Chile, M\u00e9xico, Argentina, Brasil y Uruguay.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2024 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26925\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26925\" aria-expanded=\"false\" aria-controls=\"collapse-26925\">\n                                            AIJ support grant for organizing the Third Latin American Summer School on Cognitive Robotics\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26925\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26925\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Fondos para apoyar la realizacion de la Third Latin American Summer School on Cognitive Robotics (LACORO 2024). La primera edici\u00f3n se realiz\u00f3 online en octubre de 2020; la segunda fue presencial en enero de 2023; la tercera versi\u00f3n tendr\u00e1 lugar entre el 9 y el 13 de diciembre de 2024 en la Universidad de O'Higgins en Rancagua, Chile. https:\/\/lacoro.org\/\r\n\r\nEsta Escuela de Verano beneficiar\u00e1 principalmente a Estudiantes y Acad\u00e9micos de las Am\u00e9ricas interesados en la Investigaci\u00f3n en Inteligencia Artificial aplicada a la Rob\u00f3tica. Nuestro objetivo es fomentar la colaboraci\u00f3n nacional y regional en esta \u00e1rea de investigaci\u00f3n. Para la primera edici\u00f3n, alcanzamos 241 inscripciones para actividades online de todo el mundo, y la segunda versi\u00f3n tuvo 166 inscripciones para actividades presenciales en enero de 2023, principalmente de Chile, M\u00e9xico, Argentina, Brasil y Uruguay.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2024 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>IEEE CIS<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26101\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26101\" aria-expanded=\"false\" aria-controls=\"collapse-26101\">\n                                            IEEE CIS support grant for organizing the Third Latin American Summer School on Robotics\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26101\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26101\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Escuela de Verano Latino Americana de Robotica (LACORO)[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2024 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>IEEE CIS<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26927\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26927\" aria-expanded=\"false\" aria-controls=\"collapse-26927\">\n                                            IEEE CIS support grant for organizing the Third Latin American Summer School on Robotics\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26927\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26927\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Escuela de Verano Latino Americana de Robotica (LACORO)[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26587\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            El riesgo de no ser admitido a la escuela vecina: La experiencia de la elecci\u00f3n escolar seg\u00fan nivel de ruralidad en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26587\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26587\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Chile tiene una larga historia de implementaci\u00f3n de un mercado escolar basado en los argumentos de que la elecci\u00f3n escolar puede mejorar la calidad de la educaci\u00f3n. Esta pol\u00edtica de elecci\u00f3n escolar es una pol\u00edtica nacional, afectando a familias de zonas urbanas y tambi\u00e9n rurales. Hist\u00f3ricamente y a nivel internacional, es en el \u00e1rea urbana d\u00f3nde se dan procesos m\u00e1s intensos de elecci\u00f3n de escuela, no en la rural. Actualmente, en Chile, con un nuevo \u00edndice de ruralidad y la implementaci\u00f3n de un sistema de admisi\u00f3n centralizada, tenemos mejores datos para poder entender c\u00f3mo funciona el mercado escolar fuera de las zonas urbanas, con la posibilidad de caracterizar el fen\u00f3meno seg\u00fan niveles de ruralidad. Esta caracterizaci\u00f3n y an\u00e1lisis de las experiencias de familias y directivos de escuelas enfrentando diversas condiciones de ruralidad ser\u00e1 esencial para poder identificar los principales desaf\u00edos que se enfrentan y las pol\u00edticas m\u00e1s esenciales para mejorar las condiciones y el acceso a educaci\u00f3n de calidad. Las experiencias no son todas iguales, y as\u00ed las pol\u00edticas tienen que reconocer que la experiencia de elecci\u00f3n escolar no es homog\u00e9nea entre zonas altamente urbanas, altamente rurales e intermedias. \r\n\r\nEste proyecto busca caracterizar y analizar c\u00f3mo la realidad de la elecci\u00f3n de escuelas  var\u00eda seg\u00fan el nivel de ruralidad, utilizando un \u00edndice de ruralidad escolar (IRE) innovador (Giaconi et al., 2022) para analizar los mercados escolares, las preferencias de los postulantes y los resultados de asignaci\u00f3n en el sistema de admisi\u00f3n escolar, as\u00ed como comprender las percepciones y experiencias de los actores clave (padres y directores) en relaci\u00f3n con la oferta educativa y la movilidad escolar en dichos contextos. Espec\u00edficamente se busca: 1. Validar y extender el \u00edndice de ruralidad escolar para su uso en el an\u00e1lisis del sistema educativo de la educaci\u00f3n b\u00e1sica y la educaci\u00f3n media. 2. Describir la distribuci\u00f3n de la oferta y demanda del mercado escolar seg\u00fan el nivel de ruralidad. 3. Evaluar diferencias seg\u00fan nivel de ruralidad en el impacto de la asignaci\u00f3n a la primera preferencia en el desempe\u00f1o de los estudiantes asignados a escuelas con sobredemanda (donde la asignaci\u00f3n se realiza por loter\u00eda). 4. Caracterizar las experiencias y percepciones de apoderadas\/os respecto al proceso de elecci\u00f3n de escuela y admisi\u00f3n v\u00eda SAE, en establecimientos educacionales con ense\u00f1anza b\u00e1sica en distintos niveles de ruralidad en la Regi\u00f3n de O\u0092Higgins.\r\n\r\nPara este an\u00e1lisis se usar\u00e1n m\u00e9todos mixtos, con un an\u00e1lisis estad\u00edstico descriptivo y entrevistas en profundidad semi-estructuradas. Para el componente cuantitativo se usar\u00e1n datos administrativos del sistema de admisi\u00f3n escolar (SAE) y del Ministerio de Educaci\u00f3n (incluyendo matr\u00edcula y SIMCE) para identificar zonas que enfrentan diversas realidades con respecto al mercado escolar y evaluar c\u00f3mo esto est\u00e1 relacionado al riesgo de no acceder a su primera preferencia. En el an\u00e1lisis cualitativo se va a profundizar en lo encontrado con el an\u00e1lisis cuantitativo, utilizando entrevistas con directores de escuelas y con familias de estudiantes que reci\u00e9n est\u00e1n entrando a escuelas p\u00fablicas o particulares subvencionados en \u00e1reas con distintos niveles de ruralidad en la Regi\u00f3n de O\u0092Higgins. Estas entrevistas permitir\u00e1n un conocimiento m\u00e1s detallado de los distintos desaf\u00edos que enfrentan estos actores y las diversas necesidades que puedan ser atendidas para mejorar las experiencias de participaci\u00f3n en los mercados educativos.\r\n\r\nAdem\u00e1s de su contribuci\u00f3n al conocimiento acad\u00e9mico, este estudio tiene implicaciones pr\u00e1cticas directas para la mejora del sistema educativo en Chile. Los resultados permitir\u00e1n informar a reformas en las pol\u00edticas educativas que aborden las experiencias de familias y escuelas en diversos contextos, m\u00e1s all\u00e1 de solo lo urbano. El proyecto tambi\u00e9n contribuye a la formaci\u00f3n de nuevos investigadores, incluyendo estudiantes de pregrado y una investigadora posdoctoral que participar\u00e1n en diversas etapas de la investigaci\u00f3n. \r\n\r\nEn resumen, este proyecto busca comprender las diversas experiencias y necesidades de familias y escuelas que difieren seg\u00fan su experiencia de la ruralidad, combinando m\u00e9todos cuantitativos y cualitativos avanzados. Su enfoque hol\u00edstico y su potencial impacto en las pol\u00edticas educativas lo posicionan como un estudio crucial para mejorar la calidad del sistema educacional de Chile y de la regi\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26737\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estrategias de afrontamiento al estr\u00e9s y sexismo: validaci\u00f3n chilena del CSI para la investigaci\u00f3n en el territorio.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26737\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26737\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En un contexto de creciente preocupaci\u00f3n por los problemas de salud mental, no puede obviarse que aquellos relacionados con miedos adquiridos, ansiedad y estr\u00e9s  (justamente de los m\u00e1s prevalentes a nivel global y tambi\u00e9n en Chile), tienen una incidencia notablemente mayor en mujeres que en hombres. Adem\u00e1s de la salud mental, el estr\u00e9s impacta otras dimensiones de la salud humana as\u00ed como los contextos en los que las personas se desarrollan (educativos, laborales etc.). Por tanto, una mayor vulnerabilidad al estr\u00e9s en las mujeres supondr\u00eda riesgos y brechas de g\u00e9nero en una multiplicidad de \u00e1mbitos.\r\n\tAunque estos datos epidemiol\u00f3gicos se conocen desde hace tiempo, los factores de vulnerabilidad y resiliencia al estr\u00e9s potencialmente involucrados permanecen relativamente desconocidos y han sido solo parcialmente abordados. Mientras algunos estudios se han centrado en establecer mecanismos biol\u00f3gicos a un nivel m\u00e1s molecular, la psicolog\u00eda viene mostrando un inter\u00e9s creciente en estudiar el papel de las estrategias de afrontamiento al estr\u00e9s, las cuales estar\u00edan fuertemente determinadas tambi\u00e9n por el contexto social y cultural.  La evidencia disponible al respecto es sin embargo a\u00fan incipiente en lo que se refiere a eventuales diferencias de g\u00e9nero en el uso de estrategias de afrontamiento al estr\u00e9s como variable potencialmente relevante para entender la emergencia de problemas de salud mental.\r\nEn Chile, esta limitaci\u00f3n resulta especialmente acuciante debido a que las investigadoras no cuentan con suficientes instrumentos validados en poblaci\u00f3n chilena para el avance del conocimiento en esta \u00e1rea. Por ello, el objetivo principal del presente proyecto es validar en poblaci\u00f3n chilena uno de los inventarios de estrategias de afrontamiento al estr\u00e9s m\u00e1s ampliamente utilizado en otros pa\u00edses, a saber, el Inventario de Estrategias de Afrontamiento al Estr\u00e9s (CSI en sus siglas e Ingl\u00e9s) para el desarrollo de estas investigaciones en nuestro territorio. Para ello, se analizar\u00e1n las propiedades psicom\u00e9tricas del instrumento a partir de su versi\u00f3n espa\u00f1ola comprobando coeficientes de fiabilidad y validez. \r\nTras la validaci\u00f3n inicial del instrumento,  en una segunda fase del estudio \u00e9ste ser\u00e1 utilizado para establecer si hombres y mujeres difieren en el uso de estrategias de afrontamiento al estr\u00e9s en dos contextos espec\u00edficos. En concreto, se analizar\u00e1n eventuales diferencias de g\u00e9nero y el papel de las estrategias de afrontamiento en el estr\u00e9s percibido durante situaciones de sexismo expl\u00edcito y de amenaza ambiental como condici\u00f3n control.  En el primer caso, utilizaremos una situaci\u00f3n experimental testeada anteriormente con \u00e9xito en nuestro laboratorio. Espec\u00edficamente, se pedir\u00e1 a tres grupos de hombres y tres grupos de mujeres que participen de un juego online,  mientras reciben verbalizaciones de \u00edndole sexista. Un grupo de cada condici\u00f3n anterior ser\u00e1 expuesto a verbalizaciones sexistas de tipo hostil, otro de tipo benevolente, mientras el tercer grupo recibir\u00e1 verbalizaciones no sexistas. Posteriormente, se establecer\u00e1 la intensidad del estr\u00e9s percibido durante el juego y se identificar\u00e1 el tipo de estrategia de afrontamiento utilizada en la situaci\u00f3n experimental. Un estudio previo conducido solo con mujeres y el Inventario de Estrategias de Afrontamiento al Estr\u00e9s (CSI) en su versi\u00f3n espa\u00f1ola encontr\u00f3 que las mujeres utilizaron en general m\u00e1s estrategias de afrontamiento de tipo desadaptativo que adaptativo en general, y que el estr\u00e9s percibido fue mayor en el primer caso que en el segundo (Osses, P\u00e9rez y Angulo, en preparaci\u00f3n).  La inclusi\u00f3n de hombres en este nuevo estudio nos permitir\u00e1 comprobar si en este tipo de situaciones las mujeres despliegan estrategias desadaptativas en mayor medida que los hombres. Finalmente, en un tercer estudio se establecer\u00e1 si hombres y mujeres difieren en el uso de estrategias de afrontamiento ante estresores ambientales. Para ello,  se identificar\u00e1 la intensidad del estr\u00e9s percibido y las estrategias de afrontamiento en personas expuestas a riesgos ambientales en una zona vulnerable de nuestra regi\u00f3n.  Aunque los resultados podr\u00edan ser relevantes en s\u00ed mismos, en este proyecto particular el tercer estudio se propone como una condici\u00f3n control que permita dilucidar si eventuales diferencias de g\u00e9nero en el uso de estrategias de afrontamiento se encuentran condicionadas por el tipo de estresor (sexista o no sexista) o son m\u00e1s bien generales. Con ello se pretende finalmente contribuir tambi\u00e9n a una mejor comprensi\u00f3n de c\u00f3mo el sexismo sist\u00e9mico que sufrimos las mujeres podr\u00eda afectar a nuestro bienestar y salud mental, analizando el papel de las estrategias de afrontamiento utilizadas en estas situaciones como factores de vulnerabilidad o resiliencia.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26920\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            El riesgo de no ser admitido a la escuela vecina: La experiencia de la elecci\u00f3n escolar seg\u00fan nivel de ruralidad en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26920\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26920\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Chile tiene una larga historia de implementaci\u00f3n de un mercado escolar basado en los argumentos de que la elecci\u00f3n escolar puede mejorar la calidad de la educaci\u00f3n. Esta pol\u00edtica de elecci\u00f3n escolar es una pol\u00edtica nacional, afectando a familias de zonas urbanas y tambi\u00e9n rurales. Hist\u00f3ricamente y a nivel internacional, es en el \u00e1rea urbana d\u00f3nde se dan procesos m\u00e1s intensos de elecci\u00f3n de escuela, no en la rural. Actualmente, en Chile, con un nuevo \u00edndice de ruralidad y la implementaci\u00f3n de un sistema de admisi\u00f3n centralizada, tenemos mejores datos para poder entender c\u00f3mo funciona el mercado escolar fuera de las zonas urbanas, con la posibilidad de caracterizar el fen\u00f3meno seg\u00fan niveles de ruralidad. Esta caracterizaci\u00f3n y an\u00e1lisis de las experiencias de familias y directivos de escuelas enfrentando diversas condiciones de ruralidad ser\u00e1 esencial para poder identificar los principales desaf\u00edos que se enfrentan y las pol\u00edticas m\u00e1s esenciales para mejorar las condiciones y el acceso a educaci\u00f3n de calidad. Las experiencias no son todas iguales, y as\u00ed las pol\u00edticas tienen que reconocer que la experiencia de elecci\u00f3n escolar no es homog\u00e9nea entre zonas altamente urbanas, altamente rurales e intermedias. \r\n\r\nEste proyecto busca caracterizar y analizar c\u00f3mo la realidad de la elecci\u00f3n de escuelas  var\u00eda seg\u00fan el nivel de ruralidad, utilizando un \u00edndice de ruralidad escolar (IRE) innovador (Giaconi et al., 2022) para analizar los mercados escolares, las preferencias de los postulantes y los resultados de asignaci\u00f3n en el sistema de admisi\u00f3n escolar, as\u00ed como comprender las percepciones y experiencias de los actores clave (padres y directores) en relaci\u00f3n con la oferta educativa y la movilidad escolar en dichos contextos. Espec\u00edficamente se busca: 1. Validar y extender el \u00edndice de ruralidad escolar para su uso en el an\u00e1lisis del sistema educativo de la educaci\u00f3n b\u00e1sica y la educaci\u00f3n media. 2. Describir la distribuci\u00f3n de la oferta y demanda del mercado escolar seg\u00fan el nivel de ruralidad. 3. Evaluar diferencias seg\u00fan nivel de ruralidad en el impacto de la asignaci\u00f3n a la primera preferencia en el desempe\u00f1o de los estudiantes asignados a escuelas con sobredemanda (donde la asignaci\u00f3n se realiza por loter\u00eda). 4. Caracterizar las experiencias y percepciones de apoderadas\/os respecto al proceso de elecci\u00f3n de escuela y admisi\u00f3n v\u00eda SAE, en establecimientos educacionales con ense\u00f1anza b\u00e1sica en distintos niveles de ruralidad en la Regi\u00f3n de O\u0092Higgins.\r\n\r\nPara este an\u00e1lisis se usar\u00e1n m\u00e9todos mixtos, con un an\u00e1lisis estad\u00edstico descriptivo y entrevistas en profundidad semi-estructuradas. Para el componente cuantitativo se usar\u00e1n datos administrativos del sistema de admisi\u00f3n escolar (SAE) y del Ministerio de Educaci\u00f3n (incluyendo matr\u00edcula y SIMCE) para identificar zonas que enfrentan diversas realidades con respecto al mercado escolar y evaluar c\u00f3mo esto est\u00e1 relacionado al riesgo de no acceder a su primera preferencia. En el an\u00e1lisis cualitativo se va a profundizar en lo encontrado con el an\u00e1lisis cuantitativo, utilizando entrevistas con directores de escuelas y con familias de estudiantes que reci\u00e9n est\u00e1n entrando a escuelas p\u00fablicas o particulares subvencionados en \u00e1reas con distintos niveles de ruralidad en la Regi\u00f3n de O\u0092Higgins. Estas entrevistas permitir\u00e1n un conocimiento m\u00e1s detallado de los distintos desaf\u00edos que enfrentan estos actores y las diversas necesidades que puedan ser atendidas para mejorar las experiencias de participaci\u00f3n en los mercados educativos.\r\n\r\nAdem\u00e1s de su contribuci\u00f3n al conocimiento acad\u00e9mico, este estudio tiene implicaciones pr\u00e1cticas directas para la mejora del sistema educativo en Chile. Los resultados permitir\u00e1n informar a reformas en las pol\u00edticas educativas que aborden las experiencias de familias y escuelas en diversos contextos, m\u00e1s all\u00e1 de solo lo urbano. El proyecto tambi\u00e9n contribuye a la formaci\u00f3n de nuevos investigadores, incluyendo estudiantes de pregrado y una investigadora posdoctoral que participar\u00e1n en diversas etapas de la investigaci\u00f3n. \r\n\r\nEn resumen, este proyecto busca comprender las diversas experiencias y necesidades de familias y escuelas que difieren seg\u00fan su experiencia de la ruralidad, combinando m\u00e9todos cuantitativos y cualitativos avanzados. Su enfoque hol\u00edstico y su potencial impacto en las pol\u00edticas educativas lo posicionan como un estudio crucial para mejorar la calidad del sistema educacional de Chile y de la regi\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26962\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            El riesgo de no ser admitido a la escuela vecina: La experiencia de la elecci\u00f3n escolar seg\u00fan nivel de ruralidad en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26962\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26962\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Chile tiene una larga historia de implementaci\u00f3n de un mercado escolar basado en los argumentos de que la elecci\u00f3n escolar puede mejorar la calidad de la educaci\u00f3n. Esta pol\u00edtica de elecci\u00f3n escolar es una pol\u00edtica nacional, afectando a familias de zonas urbanas y tambi\u00e9n rurales. Hist\u00f3ricamente y a nivel internacional, es en el \u00e1rea urbana d\u00f3nde se dan procesos m\u00e1s intensos de elecci\u00f3n de escuela, no en la rural. Actualmente, en Chile, con un nuevo \u00edndice de ruralidad y la implementaci\u00f3n de un sistema de admisi\u00f3n centralizada, tenemos mejores datos para poder entender c\u00f3mo funciona el mercado escolar fuera de las zonas urbanas, con la posibilidad de caracterizar el fen\u00f3meno seg\u00fan niveles de ruralidad. Esta caracterizaci\u00f3n y an\u00e1lisis de las experiencias de familias y directivos de escuelas enfrentando diversas condiciones de ruralidad ser\u00e1 esencial para poder identificar los principales desaf\u00edos que se enfrentan y las pol\u00edticas m\u00e1s esenciales para mejorar las condiciones y el acceso a educaci\u00f3n de calidad. Las experiencias no son todas iguales, y as\u00ed las pol\u00edticas tienen que reconocer que la experiencia de elecci\u00f3n escolar no es homog\u00e9nea entre zonas altamente urbanas, altamente rurales e intermedias. \r\n\r\nEste proyecto busca caracterizar y analizar c\u00f3mo la realidad de la elecci\u00f3n de escuelas  var\u00eda seg\u00fan el nivel de ruralidad, utilizando un \u00edndice de ruralidad escolar (IRE) innovador (Giaconi et al., 2022) para analizar los mercados escolares, las preferencias de los postulantes y los resultados de asignaci\u00f3n en el sistema de admisi\u00f3n escolar, as\u00ed como comprender las percepciones y experiencias de los actores clave (padres y directores) en relaci\u00f3n con la oferta educativa y la movilidad escolar en dichos contextos. Espec\u00edficamente se busca: 1. Validar y extender el \u00edndice de ruralidad escolar para su uso en el an\u00e1lisis del sistema educativo de la educaci\u00f3n b\u00e1sica y la educaci\u00f3n media. 2. Describir la distribuci\u00f3n de la oferta y demanda del mercado escolar seg\u00fan el nivel de ruralidad. 3. Evaluar diferencias seg\u00fan nivel de ruralidad en el impacto de la asignaci\u00f3n a la primera preferencia en el desempe\u00f1o de los estudiantes asignados a escuelas con sobredemanda (donde la asignaci\u00f3n se realiza por loter\u00eda). 4. Caracterizar las experiencias y percepciones de apoderadas\/os respecto al proceso de elecci\u00f3n de escuela y admisi\u00f3n v\u00eda SAE, en establecimientos educacionales con ense\u00f1anza b\u00e1sica en distintos niveles de ruralidad en la Regi\u00f3n de O\u0092Higgins.\r\n\r\nPara este an\u00e1lisis se usar\u00e1n m\u00e9todos mixtos, con un an\u00e1lisis estad\u00edstico descriptivo y entrevistas en profundidad semi-estructuradas. Para el componente cuantitativo se usar\u00e1n datos administrativos del sistema de admisi\u00f3n escolar (SAE) y del Ministerio de Educaci\u00f3n (incluyendo matr\u00edcula y SIMCE) para identificar zonas que enfrentan diversas realidades con respecto al mercado escolar y evaluar c\u00f3mo esto est\u00e1 relacionado al riesgo de no acceder a su primera preferencia. En el an\u00e1lisis cualitativo se va a profundizar en lo encontrado con el an\u00e1lisis cuantitativo, utilizando entrevistas con directores de escuelas y con familias de estudiantes que reci\u00e9n est\u00e1n entrando a escuelas p\u00fablicas o particulares subvencionados en \u00e1reas con distintos niveles de ruralidad en la Regi\u00f3n de O\u0092Higgins. Estas entrevistas permitir\u00e1n un conocimiento m\u00e1s detallado de los distintos desaf\u00edos que enfrentan estos actores y las diversas necesidades que puedan ser atendidas para mejorar las experiencias de participaci\u00f3n en los mercados educativos.\r\n\r\nAdem\u00e1s de su contribuci\u00f3n al conocimiento acad\u00e9mico, este estudio tiene implicaciones pr\u00e1cticas directas para la mejora del sistema educativo en Chile. Los resultados permitir\u00e1n informar a reformas en las pol\u00edticas educativas que aborden las experiencias de familias y escuelas en diversos contextos, m\u00e1s all\u00e1 de solo lo urbano. El proyecto tambi\u00e9n contribuye a la formaci\u00f3n de nuevos investigadores, incluyendo estudiantes de pregrado y una investigadora posdoctoral que participar\u00e1n en diversas etapas de la investigaci\u00f3n. \r\n\r\nEn resumen, este proyecto busca comprender las diversas experiencias y necesidades de familias y escuelas que difieren seg\u00fan su experiencia de la ruralidad, combinando m\u00e9todos cuantitativos y cualitativos avanzados. Su enfoque hol\u00edstico y su potencial impacto en las pol\u00edticas educativas lo posicionan como un estudio crucial para mejorar la calidad del sistema educacional de Chile y de la regi\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI240223<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2024 - Noviembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27024\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Red de escritura cient\u00edfica con enfoque cr\u00edtico para fortalecer la elaboraci\u00f3n de trabajos acad\u00e9micos en estudiantes de lenguas de pre y postgrado.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27024\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27024\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La red de escritura cient\u00edfica con enfoque cr\u00edtico para la elaboraci\u00f3n de trabajos acad\u00e9micos en estudiantes de lenguas de pre y postgrado es una propuesta interdisciplinaria entre la ense\u00f1anza-aprendizaje de la escritura en estudiantes de pre y postgrado y la pedagog\u00eda orientada al desarrollo de consciencia ling\u00fc\u00edstica cr\u00edtica (CLA). El objetivo general es fortalecer la investigaci\u00f3n en escritura cient\u00edfica a trav\u00e9s del intercambio de conocimiento entre los pa\u00edses participantes para compartir experiencias, m\u00e9todos y recursos relacionados con la ense\u00f1anza de la escritura con enfoque cr\u00edtico a estudiantes de pre y postgrado que necesitan desarrollar su trabajo final de grado (TFG) o un art\u00edculo cient\u00edfico (AC). La colaboraci\u00f3n entre acad\u00e9micas chilenas y extranjeras que realizan su quehacer investigativo en contextos de desigualdad socioling\u00fc\u00edstica, como lo son las ciudades de Vi\u00f1a del Mar, Rancagua, Concepci\u00f3n, Nueva York y Madrid es fundamental para la operacionalizaci\u00f3n de la red. El equipo inicial est\u00e1 compuesto por las doctoras Steffanie Kloss (investigadora responsable), Chenda Ram\u00edrez (co-investigadora), Tania Avil\u00e9s, Angie Quintanilla y Emmy Gonz\u00e1lez (investigadoras nacionales asociadas), Evelyn Dur\u00e1n (investigadora de instituci\u00f3n extranjera), Beatriz Lado (investigadora de instituci\u00f3n extranjera) y Mar\u00eda Teresa Mateo (investigadora de instituci\u00f3n extranjera). Esta red de colaboraci\u00f3n es preexistente, puesto que la investigadora principal colabora con las acad\u00e9micas de la instituci\u00f3n extranjera Lehman College desde 2023, cuando desarroll\u00f3 una pasant\u00eda postdoctoral en el marco de su proyecto Fondecyt y con la Universidad Complutense de Madrid desde 2024, a\u00f1o en que realiz\u00f3 una pasant\u00eda de investigaci\u00f3n con la Dra. Mateo, quien es directora del grupo DIDACTEXT. Adem\u00e1s, la Dra. Avil\u00e9s ha trabajado desde el a\u00f1o 2021 con el equipo de Nueva York, con quienes ha publicado art\u00edculos de corriente principal y ha participado en congresos relacionados a la CLA. Asimismo, la Dra. Gonz\u00e1lez, ha trabajado con la Dra. Mateo-Girona desde 2021 y han publicado art\u00edculos de investigaci\u00f3n cient\u00edfica de manera conjunta. El equipo completo tiene una vasta experiencia en escritura acad\u00e9mica, retroalimentaci\u00f3n y enfoque cr\u00edtico.\r\n\r\n\r\nLa red busca generar un intercambio de conocimiento entre los pa\u00edses participantes para compartir experiencias, m\u00e9todos y recursos relacionados con la ense\u00f1anza de la escritura cient\u00edfica con enfoque cr\u00edtico a estudiantes de pre y postgrado que necesitan desarrollar su trabajo final de grado a partir de la escritura de un art\u00edculo cient\u00edfico. De este modo, los estudiantes provenientes de contextos de diversidad ling\u00fc\u00edstica y geogr\u00e1fica podr\u00e1n intercambiar estrategias exitosas para mejorar la elaboraci\u00f3n de textos que le permitan cerrar su ciclo acad\u00e9mico en pre y postgrado, tales como Trabajo Final de Grado (TFG) y Art\u00edculo Cient\u00edfico (AC) y, al mismo tiempo, fomentar la conciencia ling\u00fc\u00edstica cr\u00edtica con respecto a la escritura en contextos acad\u00e9micos. La escritura acad\u00e9mica, como habilidad y g\u00e9nero, es un aprendizaje inculcado e impuesto en el sistema educativo formal, por lo que es importante que el estudiantado reflexione cr\u00edticamente sobre los beneficios y sanciones sociales e incluso econ\u00f3micas que puedan experimentar debido al conocimiento o desconocimiento de este tipo de escritura. Con este proyecto, se busca mejorar los procesos de aprendizaje de la escritura acad\u00e9mica para cumplir con est\u00e1ndares universitarios, pero al mismo tiempo fomentar conciencia cr\u00edtica en torno al valor de este capital ling\u00fc\u00edstico en el campo acad\u00e9mico y laboral ,y explorar c\u00f3mo esto intersecta con sus identidades e inter\u00e9s por aprender la escritura acad\u00e9mica. Adem\u00e1s, la promoci\u00f3n de la diversidad cultural y ling\u00fc\u00edstica que rodea la ense\u00f1anza-aprendizaje de la escritura acad\u00e9mica permitir\u00eda a los estudiantes desarrollar una mayor sensibilidad hacia las distintas formas de expresi\u00f3n ling\u00fc\u00edstica y a respetar las diferencias culturales, lo que se traduce en investigaci\u00f3n conjunta. Estos beneficios podr\u00edan tener un impacto positivo en la elaboraci\u00f3n de sus textos, pues no s\u00f3lo conocer\u00e1n estructuras ret\u00f3ricas que faciliten su escritura, sino tambi\u00e9n podr\u00e1n dialogar con expertas en el \u00e1mbito y formar parte de una red de colaboraci\u00f3n de escritura y di\u00e1logo con otros estudiantes. \r\nEn este contexto, los objetivos espec\u00edficos de la red son: 1) Caracterizar, con la colaboraci\u00f3n de las acad\u00e9micas extranjeras, las experiencias socioculturales y representaciones en torno a la escritura de la poblaci\u00f3n estudiantil que les permitan mejorar sus pr\u00e1cticas de escritura cient\u00edfica en la instituci\u00f3n principal y asociadas; 2) dise\u00f1ar, con la colaboraci\u00f3n de las acad\u00e9micas extranjeras, intervenciones did\u00e1cticas que incorporen la perspectiva CLA a la ense\u00f1anza de escritura cient\u00edfica, a la luz de las necesidades anteriormente identificadas, en asignaturas de final de carrera en Vi\u00f1a del Mar, Rancagua y Concepci\u00f3n; 3) publicar en revistas acad\u00e9micas y en conferencias los resultados de las investigaciones desarrolladas; 4) capacitar, a trav\u00e9s de dos seminarios multilaterales, a profesores y estudiantes de pre y postgrado (Vi\u00f1a del Mar y Concepci\u00f3n) en el dise\u00f1o, implementaci\u00f3n y evaluaci\u00f3n de pedagog\u00edas orientadas al desarrollo de conciencia ling\u00fc\u00edstica cr\u00edtica en la ense\u00f1anza de escritura cient\u00edfica en Chile; y 5) establecer una red de escritura cient\u00edfica con enfoque cr\u00edtico para fortalecer la elaboraci\u00f3n de trabajos acad\u00e9micos en estudiantes de lenguas de pre y postgrado, que promueva la conciencia cr\u00edtica en la ense\u00f1anza de la escritura cient\u00edfica de estudiantes con diferentes lenguas de origen que cursen pre o postgrado. \r\nPara llevar a cabo estos objetivos, se han seleccionado las modalidades A y C, puesto que proyectamos actividades de capacitaci\u00f3n para el equipo nacional (i.e. entrenamiento en secuencias did\u00e1cticas para ense\u00f1ar escritura cient\u00edfica y la participaci\u00f3n en un seminario internacional de did\u00e1ctica de la escritura en Madrid y realizaci\u00f3n de dos seminarios bilaterales (i.e. actividades centrales de difusi\u00f3n), una en la zona central (Vi\u00f1a del Mar) y otra en la Zona centro sur (Concepci\u00f3n). De esta manera, a partir de las dos modalidades seleccionadas se cubrir\u00e1n aspectos relativos a: a) capacitaci\u00f3n de capital humano nacional, b) afianzamiento de redes de colaboraci\u00f3n e innovaci\u00f3n en la investigaci\u00f3n nacional, y c) difusi\u00f3n y socializaci\u00f3n de metodolog\u00edas y resultados nacionales, a nivel local e internacional. Entre los resultados, se espera mejorar la escritura cient\u00edfica de los g\u00e9neros Trabajo Final de Grado (TFG) y Art\u00edculo Cient\u00edfico (AC) mediante el desarrollo de conciencia ling\u00fc\u00edstica cr\u00edtica. Con la realizaci\u00f3n de este proyecto, esperamos introducir una nueva metodolog\u00eda educativa que apoye la did\u00e1ctica de la escritura cient\u00edfica en contexto regional, reforzar la red preexistente con nuevos datos y publicaciones, y ampliar el alcance que han tenido hasta ahora las pedagog\u00edas CLA con relaci\u00f3n a la escritura cient\u00edfica.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI240258<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2024 - Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26057\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Vinculaci\u00f3n internacional para la mejora de procesos de destete precoz en producciones intensivas de cerdos mediante una mirada hol\u00edstica y transdisciplinar que mejore la sostenibilidad de la industria.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26057\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26057\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Vinculaci\u00f3n internacional con la Universidad autonoma de Barcelona (Francisco Perez) y nacional con la Universidad de Chile (Daniela Luna) para el estudio de destetes prematuros en cerdos producidos intensivamente y su relaci\u00f3n con afecciones fisiol\u00f3gicas y de bienestar.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI240258<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2024 - Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26241\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Vinculaci\u00f3n internacional para la mejora de procesos de destete precoz en producciones intensivas de cerdos mediante una mirada hol\u00edstica y transdisciplinar que mejore la sostenibilidad de la industria.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26241\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26241\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Vinculaci\u00f3n internacional con la Universidad autonoma de Barcelona (Francisco Perez) y nacional con la Universidad de Chile (Daniela Luna) para el estudio de destetes prematuros en cerdos producidos intensivamente y su relaci\u00f3n con afecciones fisiol\u00f3gicas y de bienestar.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26503\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Masculinidades y sus distintas expresiones: Actitudes y creencias sobre las masculinidades y sus relaciones con normas, roles, estereotipos de g\u00e9nero y sexismo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26503\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26503\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El concepto de masculinidad no es fijo ni universal, sino que est\u00e1 en constante construcci\u00f3n y evoluci\u00f3n, y\r\nest\u00e1 influido por contextos hist\u00f3ricos y socioculturales espec\u00edficos. As\u00ed, las masculinidades hegem\u00f3nicas\r\nrepresentan ideas dominantes sobre c\u00f3mo deben ser los hombres (y por asociaci\u00f3n las mujeres),\r\nestableciendo normas que refuerzan estructuras de poder y de dominaci\u00f3n que subordinan la mujer a\r\nestructuras jer\u00e1rquicas en las cu\u00e1les el hombre concentra diversas formas de poder, tales como el econ\u00f3mico,\r\npol\u00edtico, social y tambi\u00e9n simb\u00f3lico. Estas normas tambi\u00e9n afectan las relaciones sexo-gen\u00e9ricas, promoviendo\r\nroles y estereotipos que privilegian lo masculino sobre lo femenino.\r\n\r\nSin embargo, en las \u00faltimas d\u00e9cadas han surgido cr\u00edticas y alternativas a estas concepciones hegem\u00f3nicas. Por\r\nejemplo, investigaciones recientes destacan masculinidades alternativas como las cuidadoras, que enfatizan\r\nvalores de cuidado y emocionalidad positiva, y las inclusivas, que valoran la diversidad de g\u00e9nero y rompen\r\ncon la heteronormatividad. Adem\u00e1s, se exploran formas m\u00e1s fluidas de identidad de g\u00e9nero, como las\r\nidentidades queer, que cuestionan el binarismo tradicional entre masculino y femenino.\r\n\r\nPor otro lado, es importante mencionar que existen diversos fen\u00f3menos negativos asociados con otros tipos\r\nde masculinidades, tales como la t\u00f3xica y la hipermasculinidad, siendo que ambas refuerzan comportamientos\r\nagresivos y da\u00f1inos hacia mujeres y hombres que se desv\u00edan de estos patrones de masculinidad.\r\n\r\nSiendo que, el \u00e1mbito universitario, con su diversidad, es un espacio clave para estudiar estas din\u00e1micas y\r\npromover cambios hacia una mayor equidad de g\u00e9nero, este proyecto tiene como objetivo explorar las\r\nactitudes y creencias de estudiantes de pregrado de la Universidad de O\u0092Higgins hacia distintos tipos de\r\nmasculinidades y su relaci\u00f3n con roles, normas de g\u00e9nero, sexismo, y pol\u00edticas de equidad, con un enfoque en\r\nlas diferencias entre hombres y mujeres heterosexuales, personas que se autoadscriben a las disidencias\r\nsexuales.\r\n\r\nPara lograr este objetivo principal, se realizar\u00e1 un estudio cuantitativo correlacional de corte transversal entre\r\nel estudiantado de la UOH. Se espera que los resultados del proyecto sean publicados en una revista cient\u00edfica\r\nde alto impacto. Por otro lado, esperamos que los principales hallazgos puedan informar la creaci\u00f3n y\/o\r\nmejora de distintas iniciativas, pol\u00edticas y programas para reducir las consecuencias negativas del sexismo, la\r\nhomofobia y otras formas de discriminaci\u00f3n de g\u00e9nero tanto en la comunidad universitaria como en la\r\nsociedad civil. Finalmente, esperamos tambi\u00e9n generar espacios de aprendizaje y di\u00e1logo con el estudiantado\r\nUOH sobre estos temas a trav\u00e9s de la realizaci\u00f3n de grupos de lectura.\r\n\r\nEsperamos que este proyecto no solo contribuya de manera te\u00f3rica al desarrollo del conocimiento en esta\r\n\u00e1rea cient\u00edfica, sino tambi\u00e9n que tenga un impacto social positivo tanto en la comunidad universitaria como\r\nen la regi\u00f3n de O\u0092Higgins y, potencialmente, el pa\u00eds.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26550\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Migraci\u00f3n en Chile: \u00bfIntegraci\u00f3n o exclusi\u00f3n? Un an\u00e1lisis de los encuadres medi\u00e1ticos y narrativas gubernamentales en Instagram.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26550\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26550\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Los conflictos militares no resueltos y las desigualdades persistentes entre pa\u00edses desarrollados y menos desarrollados hacen de la migraci\u00f3n un tema prioritario en las agendas p\u00fablicas y pol\u00edticas globales. Los medios de comunicaci\u00f3n han fomentado la percepci\u00f3n de la migraci\u00f3n como crisis, a menudo present\u00e1ndola como un problema (Stefoni el al., 2023). La representaci\u00f3n de la migraci\u00f3n como un problema es prominente en los medios, influenciando la opini\u00f3n p\u00fablica y generando actitudes negativas hacia los inmigrantes. Sin embargo, existe poca evidencia sistem\u00e1tica sobre c\u00f3mo el Gobierno chileno representa la migraci\u00f3n a nivel oficial. \r\nEste proyecto analiza c\u00f3mo los medios influencian las percepciones p\u00fablicas sobre la migraci\u00f3n en Chile, centr\u00e1ndose en el Servicio Nacional de Migraciones. Particularmente, se investiga la forma en que el Gobierno chileno comunica informaciones relativas a los inmigrantes durante el mandato de Gabriel Boric (2022-2024), desde su cuenta oficial de Instagram, enfoc\u00e1ndose en la configuraci\u00f3n de la agenda y el encuadre medi\u00e1tico. Es por ello por lo que el objetivo principal es analizar los encuadres medi\u00e1ticos sobre inmigraci\u00f3n en la cuenta oficial de Instagram del Servicio Nacional de Migraciones durante el gobierno de Gabriel Boric. Los objetivos espec\u00edficos son: \r\n\r\nIdentificar los encuadres medi\u00e1ticos m\u00e1s prominentes sobre inmigraci\u00f3n en Instagram del Servicio Nacional de Migraciones.\r\nAnalizar c\u00f3mo se construye discursivamente la migraci\u00f3n en dicha plataforma.\r\n\r\nEl estudio utilizar\u00e1 la herramienta Crowtangle para recolectar publicaciones de Instagram del Servicio Nacional de Migraciones, de marzo 2022 a marzo 2024. Se realizar\u00e1 un an\u00e1lisis de contenido cualitativo manual utilizando el software Atlas.Ti. Se identificar\u00e1n palabras clave, im\u00e1genes y otros elementos significativos para evaluar c\u00f3mo se enmarcan los temas inmigratorios. Adicionalmente, se utilizar\u00e1 el Enfoque Hist\u00f3rico-Discursivo para evaluar la construcci\u00f3n discursiva de las publicaciones, complementando con taxonom\u00edas de representaci\u00f3n de actores sociales y an\u00e1lisis de hashtags. Esta metodolog\u00eda mixta ayudar\u00e1 a revelar patrones en la manera en que el Gobierno chileno comunica la migraci\u00f3n y c\u00f3mo influye en las actitudes p\u00fablicas hacia este fen\u00f3meno.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26721\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Migraci\u00f3n en Chile: \u00bfIntegraci\u00f3n o exclusi\u00f3n? Un an\u00e1lisis de los encuadres medi\u00e1ticos y narrativas gubernamentales en Instagram.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26721\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26721\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Los conflictos militares no resueltos y las desigualdades persistentes entre pa\u00edses desarrollados y menos desarrollados hacen de la migraci\u00f3n un tema prioritario en las agendas p\u00fablicas y pol\u00edticas globales. Los medios de comunicaci\u00f3n han fomentado la percepci\u00f3n de la migraci\u00f3n como crisis, a menudo present\u00e1ndola como un problema (Stefoni el al., 2023). La representaci\u00f3n de la migraci\u00f3n como un problema es prominente en los medios, influenciando la opini\u00f3n p\u00fablica y generando actitudes negativas hacia los inmigrantes. Sin embargo, existe poca evidencia sistem\u00e1tica sobre c\u00f3mo el Gobierno chileno representa la migraci\u00f3n a nivel oficial. \r\nEste proyecto analiza c\u00f3mo los medios influencian las percepciones p\u00fablicas sobre la migraci\u00f3n en Chile, centr\u00e1ndose en el Servicio Nacional de Migraciones. Particularmente, se investiga la forma en que el Gobierno chileno comunica informaciones relativas a los inmigrantes durante el mandato de Gabriel Boric (2022-2024), desde su cuenta oficial de Instagram, enfoc\u00e1ndose en la configuraci\u00f3n de la agenda y el encuadre medi\u00e1tico. Es por ello por lo que el objetivo principal es analizar los encuadres medi\u00e1ticos sobre inmigraci\u00f3n en la cuenta oficial de Instagram del Servicio Nacional de Migraciones durante el gobierno de Gabriel Boric. Los objetivos espec\u00edficos son: \r\n\r\nIdentificar los encuadres medi\u00e1ticos m\u00e1s prominentes sobre inmigraci\u00f3n en Instagram del Servicio Nacional de Migraciones.\r\nAnalizar c\u00f3mo se construye discursivamente la migraci\u00f3n en dicha plataforma.\r\n\r\nEl estudio utilizar\u00e1 la herramienta Crowtangle para recolectar publicaciones de Instagram del Servicio Nacional de Migraciones, de marzo 2022 a marzo 2024. Se realizar\u00e1 un an\u00e1lisis de contenido cualitativo manual utilizando el software Atlas.Ti. Se identificar\u00e1n palabras clave, im\u00e1genes y otros elementos significativos para evaluar c\u00f3mo se enmarcan los temas inmigratorios. Adicionalmente, se utilizar\u00e1 el Enfoque Hist\u00f3rico-Discursivo para evaluar la construcci\u00f3n discursiva de las publicaciones, complementando con taxonom\u00edas de representaci\u00f3n de actores sociales y an\u00e1lisis de hashtags. Esta metodolog\u00eda mixta ayudar\u00e1 a revelar patrones en la manera en que el Gobierno chileno comunica la migraci\u00f3n y c\u00f3mo influye en las actitudes p\u00fablicas hacia este fen\u00f3meno.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26763\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Masculinidades y sus distintas expresiones: Actitudes y creencias sobre las masculinidades y sus relaciones con normas, roles, estereotipos de g\u00e9nero y sexismo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26763\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26763\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El concepto de masculinidad no es fijo ni universal, sino que est\u00e1 en constante construcci\u00f3n y evoluci\u00f3n, y\r\nest\u00e1 influido por contextos hist\u00f3ricos y socioculturales espec\u00edficos. As\u00ed, las masculinidades hegem\u00f3nicas\r\nrepresentan ideas dominantes sobre c\u00f3mo deben ser los hombres (y por asociaci\u00f3n las mujeres),\r\nestableciendo normas que refuerzan estructuras de poder y de dominaci\u00f3n que subordinan la mujer a\r\nestructuras jer\u00e1rquicas en las cu\u00e1les el hombre concentra diversas formas de poder, tales como el econ\u00f3mico,\r\npol\u00edtico, social y tambi\u00e9n simb\u00f3lico. Estas normas tambi\u00e9n afectan las relaciones sexo-gen\u00e9ricas, promoviendo\r\nroles y estereotipos que privilegian lo masculino sobre lo femenino.\r\n\r\nSin embargo, en las \u00faltimas d\u00e9cadas han surgido cr\u00edticas y alternativas a estas concepciones hegem\u00f3nicas. Por\r\nejemplo, investigaciones recientes destacan masculinidades alternativas como las cuidadoras, que enfatizan\r\nvalores de cuidado y emocionalidad positiva, y las inclusivas, que valoran la diversidad de g\u00e9nero y rompen\r\ncon la heteronormatividad. Adem\u00e1s, se exploran formas m\u00e1s fluidas de identidad de g\u00e9nero, como las\r\nidentidades queer, que cuestionan el binarismo tradicional entre masculino y femenino.\r\n\r\nPor otro lado, es importante mencionar que existen diversos fen\u00f3menos negativos asociados con otros tipos\r\nde masculinidades, tales como la t\u00f3xica y la hipermasculinidad, siendo que ambas refuerzan comportamientos\r\nagresivos y da\u00f1inos hacia mujeres y hombres que se desv\u00edan de estos patrones de masculinidad.\r\n\r\nSiendo que, el \u00e1mbito universitario, con su diversidad, es un espacio clave para estudiar estas din\u00e1micas y\r\npromover cambios hacia una mayor equidad de g\u00e9nero, este proyecto tiene como objetivo explorar las\r\nactitudes y creencias de estudiantes de pregrado de la Universidad de O\u0092Higgins hacia distintos tipos de\r\nmasculinidades y su relaci\u00f3n con roles, normas de g\u00e9nero, sexismo, y pol\u00edticas de equidad, con un enfoque en\r\nlas diferencias entre hombres y mujeres heterosexuales, personas que se autoadscriben a las disidencias\r\nsexuales.\r\n\r\nPara lograr este objetivo principal, se realizar\u00e1 un estudio cuantitativo correlacional de corte transversal entre\r\nel estudiantado de la UOH. Se espera que los resultados del proyecto sean publicados en una revista cient\u00edfica\r\nde alto impacto. Por otro lado, esperamos que los principales hallazgos puedan informar la creaci\u00f3n y\/o\r\nmejora de distintas iniciativas, pol\u00edticas y programas para reducir las consecuencias negativas del sexismo, la\r\nhomofobia y otras formas de discriminaci\u00f3n de g\u00e9nero tanto en la comunidad universitaria como en la\r\nsociedad civil. Finalmente, esperamos tambi\u00e9n generar espacios de aprendizaje y di\u00e1logo con el estudiantado\r\nUOH sobre estos temas a trav\u00e9s de la realizaci\u00f3n de grupos de lectura.\r\n\r\nEsperamos que este proyecto no solo contribuya de manera te\u00f3rica al desarrollo del conocimiento en esta\r\n\u00e1rea cient\u00edfica, sino tambi\u00e9n que tenga un impacto social positivo tanto en la comunidad universitaria como\r\nen la regi\u00f3n de O\u0092Higgins y, potencialmente, el pa\u00eds.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2024 - Noviembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26861\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Contribuci\u00f3n a la gesti\u00f3n del riesgo por ca\u00edda de rocas y erosi\u00f3n para el fomento de un geoturismo seguro a trav\u00e9s de la geolog\u00eda aplicada en Rapa Nui.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26861\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26861\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Rapa Nui o Isla de Pascua es una isla volc\u00e1nica intraoce\u00e1nica que se encuentra sobre la placa de Nazca, ubicada en el v\u00e9rtice oriental de la Polinesia (Oc\u00e9ano Pac\u00edfico). La isla se encuentra a 3700 km de la costa continental chilena y pertenece a la Regi\u00f3n de Valpara\u00edso (Chile). Su situaci\u00f3n remota y aislada junto con el aumento de la urbanizaci\u00f3n, la ocupaci\u00f3n y el turismo en el territorio, se traduce en mayores niveles de exposici\u00f3n y de vulnerabilidad frente a peligros geol\u00f3gicos como el volcanismo, la erosi\u00f3n, las remociones en masa, los tsunamis, entre otros, que generan niveles relativamente altos de riesgo local.\r\nEl 40% del \u00e1rea insular corresponde al Parque Nacional Rapa Nui, donde existen lugares de alto inter\u00e9s y visita por su riqueza arqueol\u00f3gica, como el volc\u00e1n Rano Raraku, la cantera de los Moai y las cuevas volc\u00e1nicas del sector Roiho. Sin embargo, actualmente estos lugares presentan riesgos de inestabilidad por ca\u00edda de rocas que amenazan tanto a locales, visitantes y al propio patrimonio cultural. Adem\u00e1s, los fen\u00f3menos hidrometeorol\u00f3gicos, cada vez m\u00e1s extremos como consecuencia del cambio clim\u00e1tico actual, van agravando la condici\u00f3n de los materiales expuestos y aumentando la tasa de denudaci\u00f3n en el territorio. La erosi\u00f3n, generada principalmente por la lluvia y el viento, es otro problema significativo, que afecta gravemente a los suelos de la isla, y que se ve principalmente en la incisi\u00f3n de la quebrada Ava Ranga Uka. A pesar de la importancia e implicancia que tienen estos fen\u00f3menos en la seguridad de quienes habitan y visitan Rapa Nui, no se han realizado estudios sobre la evaluaci\u00f3n de los peligros geol\u00f3gicos asociados a las remociones en masa o la erosi\u00f3n superficial.\r\nEste proyecto busca, por tanto, evaluar los procesos de denudaci\u00f3n para comprender la influencia de los fen\u00f3menos de remociones en masa (ca\u00edda de roca) y erosi\u00f3n por escorrent\u00eda superficial en la estabilidad del paisaje, que representan un riesgo geol\u00f3gico para en diferentes lugares altamente visitados. Para ello, se caracterizar\u00e1n geot\u00e9cnicamente los macizos rocosos con el objetivo de evaluar la estabilidad del paleoacantilado del cono Rano Raraku y las cuevas Ana Kakenga y Ana Te Pahu a trav\u00e9s de ensayos de laboratorio, datos en terreno y el uso de un l\u00e1ser esc\u00e1ner. Adem\u00e1s, se realizar\u00e1 la identificaci\u00f3n de los factores que influyen en la inestabilidad y se localizaran las zonas de alcance ante el potencial peligro de ca\u00edda de rocas a trav\u00e9s del software RocScience. Por otro lado, para evaluar la erosi\u00f3n por escorrent\u00eda se determinar\u00e1n las tasas de erosi\u00f3n superficial utilizando is\u00f3topos cosmog\u00f3nicos (3He) de sedimentos de la quebrada Ava Ranga Uka. Los resultados, adem\u00e1s de arrojar luz sobre la din\u00e1mica y evoluci\u00f3n de los procesos de denudaci\u00f3n en la isla, servir\u00e1n para desarrollar planes de seguridad y conservaci\u00f3n, asegurando la protecci\u00f3n del patrimonio cultural y la seguridad de residentes y turistas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26908\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Evaluaci\u00f3n del potencial de captura de carbono en relaves mineros de la Mina El Teniente, Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26908\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26908\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Evaluaci\u00f3n del potencial de captura de carbono en relaves mineros de la Mina El Teniente, Chile[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27023\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Migraci\u00f3n en Chile: \u00bfIntegraci\u00f3n o exclusi\u00f3n? Un an\u00e1lisis de los encuadres medi\u00e1ticos y narrativas gubernamentales en Instagram.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27023\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27023\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Los conflictos militares no resueltos y las desigualdades persistentes entre pa\u00edses desarrollados y menos desarrollados hacen de la migraci\u00f3n un tema prioritario en las agendas p\u00fablicas y pol\u00edticas globales. Los medios de comunicaci\u00f3n han fomentado la percepci\u00f3n de la migraci\u00f3n como crisis, a menudo present\u00e1ndola como un problema (Stefoni el al., 2023). La representaci\u00f3n de la migraci\u00f3n como un problema es prominente en los medios, influenciando la opini\u00f3n p\u00fablica y generando actitudes negativas hacia los inmigrantes. Sin embargo, existe poca evidencia sistem\u00e1tica sobre c\u00f3mo el Gobierno chileno representa la migraci\u00f3n a nivel oficial. \r\nEste proyecto analiza c\u00f3mo los medios influencian las percepciones p\u00fablicas sobre la migraci\u00f3n en Chile, centr\u00e1ndose en el Servicio Nacional de Migraciones. Particularmente, se investiga la forma en que el Gobierno chileno comunica informaciones relativas a los inmigrantes durante el mandato de Gabriel Boric (2022-2024), desde su cuenta oficial de Instagram, enfoc\u00e1ndose en la configuraci\u00f3n de la agenda y el encuadre medi\u00e1tico. Es por ello por lo que el objetivo principal es analizar los encuadres medi\u00e1ticos sobre inmigraci\u00f3n en la cuenta oficial de Instagram del Servicio Nacional de Migraciones durante el gobierno de Gabriel Boric. Los objetivos espec\u00edficos son: \r\n\r\nIdentificar los encuadres medi\u00e1ticos m\u00e1s prominentes sobre inmigraci\u00f3n en Instagram del Servicio Nacional de Migraciones.\r\nAnalizar c\u00f3mo se construye discursivamente la migraci\u00f3n en dicha plataforma.\r\n\r\nEl estudio utilizar\u00e1 la herramienta Crowtangle para recolectar publicaciones de Instagram del Servicio Nacional de Migraciones, de marzo 2022 a marzo 2024. Se realizar\u00e1 un an\u00e1lisis de contenido cualitativo manual utilizando el software Atlas.Ti. Se identificar\u00e1n palabras clave, im\u00e1genes y otros elementos significativos para evaluar c\u00f3mo se enmarcan los temas inmigratorios. Adicionalmente, se utilizar\u00e1 el Enfoque Hist\u00f3rico-Discursivo para evaluar la construcci\u00f3n discursiva de las publicaciones, complementando con taxonom\u00edas de representaci\u00f3n de actores sociales y an\u00e1lisis de hashtags. Esta metodolog\u00eda mixta ayudar\u00e1 a revelar patrones en la manera en que el Gobierno chileno comunica la migraci\u00f3n y c\u00f3mo influye en las actitudes p\u00fablicas hacia este fen\u00f3meno.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1324000<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2024 - Noviembre 2028<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27048\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Natural Hydrogen in Chile: Unlocking the Geological Sources for a Green Energy Transition\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27048\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27048\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]As the world explores alternatives to fossil fuels, hydrogen (H&#8322;) has emerged as a critical element in accelerating the transition to clean and renewable energy sources (Gaucher et al., 2023; Le et al., 2023; Blay-Roger et al., 2024). Unlike gasoline, which emits CO2 when burned, H&#8322; combustion produces only water vapor, making it a high-quality and environmentally friendly fuel alternative. Hydrogen is primarily produced for industry processes, including \u0093green hydrogen\u0094, \u0093blue hydrogen\u0094, and \u0093gray hydrogen\u0094 (IEA, 2019). On the other hand, the so-called \u0093natural\u0094 or \u0093white hydrogen\u0094 is potentially a more cost-effective and environmentally friendly alternative because it is ready to be used for energy production, without the need for polluting processes to obtain it (Smith et al., 2005; Lapi et al., 2022; Gaucher et al., 2023; Blay-Roger et al., 2024). However, H&#8322; accumulation in the subsurface has been largely overlooked due to assumptions of its rarity or nonexistence, attributed to the hydrogen's inheritance characteristics (small and reactive molecule). The first fortuitous discoveries in the USA or Mali (West Africa) proved that it was a mistake (Zgonnik, 2020).\r\n\r\nCurrently, the geological processes that generate natural hydrogen have started to be better understood, but the conditions for its accumulation remain poorly constrained (L\u00e9vy et al., 2023). The potential for global extraction of natural hydrogen is significant, so it is critical that we understand how it is generated, transported, and ultimately trapped. Recent discoveries of natural hydrogen in various geological settings, including mid-ocean ridges, ophiolitic nappes, transform faults, convergent subduction margins, and intraplate settings (Zgonnik et al., 2020; Jackson et al., 2024) highlight the increasing interest in this resource. As a result, exploration projects are currently active in several countries such as Australia, the USA, France, Spain, and South America (e.g., Zgonnik et al., 2020, Jackson et al., 2024). Experience in managing H&#8322; reservoirs is obviously still missing, but the analogies should perhaps rather be sought in the field of geothermal energy (Moretti et al., 2023).\r\n\r\nIn terms of geotectonic settings of natural hydrogen formation, subduction zones represent the primary geological environment for the large-scale interaction between water and mantle peridotite, i.e., serpentinization processes (Zgonnik et al., 2020). Serpentinization is the most effective and hence important subsurface process for producing and focusing natural hydrogen in potentially commercial volumes (Jackson et al., 2024). Particularly, in the Central Andean Volcanic Zone (CAVZ; 18-28\u00b0S; Fig. 1a) only a limited number of investigations have focused on natural hydrogen data. Moretti et al. (2023) confirmed the presence of natural hydrogen in the Bolivian Altiplano (e.g., Pampa Lirima and Sol de Ma\u00f1ana; Fig. 1a) by using geochemical measurements of gasses from hot springs and in-situ analysis of soil gas. Moreover, the 3He\/4He ratios in the Altiplano-Puna plateau indicate that the amount of He uprising from the mantle (i.e., 3He content) is very large (Fig. 1b). This indicates that deep gasses are migrating toward the overriding plate surface above subduction (Fig. 1c). Based on the findings of Moretti et al. (2023), it is highly probable to find natural hydrogen in the Chilean portion of the Altiplano. In this context, the proposed research plans to unlock the geological origin and assess the potential of natural hydrogen in northern Chile. Moreover, this project goes one step further than the study of Moretti et al. (2023) and proposes to investigate the potential occurrences of natural hydrogen associated with specific structural arrangements related to volcanic and geothermal systems (Veloso et al., 2019). For that reason, the acquisition of new geological, structural, geochemical, seismological, and geophysical data is crucial to better understand natural hydrogen systems and to determine the prospectivity of new areas in Chile.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27066\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Evaluaci\u00f3n del potencial de captura de carbono en relaves mineros de la Mina El Teniente, Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27066\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27066\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Evaluaci\u00f3n del potencial de captura de carbono en relaves mineros de la Mina El Teniente, Chile[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2024 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26100\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            KhipuX grant for organizing the Third Latin American Summer School on Cognitive Robotics\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26100\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26100\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]KhipuX support grant for organizing the Third Latin American Summer School on Cognitive Robotics (LACORO) https:\/\/www.lacoro.org\/[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2024 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26926\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            KhipuX grant for organizing the Third Latin American Summer School on Cognitive Robotics\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26926\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26926\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]KhipuX support grant for organizing the Third Latin American Summer School on Cognitive Robotics (LACORO) https:\/\/www.lacoro.org\/[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI 240094<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26993\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estudios Socio Jur\u00eddicos: Ampliando los Horizontes de los Estudios del Derecho para Satisfacer las Necesidades profesionales en sociedades complejas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26993\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26993\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto tiene por objetivo general establecer una red internacional de investigaci\u00f3n y ense\u00f1anza sociolegal centrada en la Universidad de O\u0092Higgins, creando un polo de innovaci\u00f3n regional en el estudio interdisciplinario del derecho.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2024 - Noviembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26315\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Cambio clim\u00e1tico y riesgos alimentarios: Evaluaci\u00f3n con enfoque de g\u00e9nero de los factores que afectan la intenci\u00f3n de adopci\u00f3n de pr\u00e1cticas de inocuidad alimentaria en agricultura y apicultura\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26315\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26315\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto aborda los desaf\u00edos actuales relacionados con la inocuidad alimentaria en la Regi\u00f3n de O'Higgins, particularmente en el contexto de cambio clim\u00e1tico. Esta regi\u00f3n, crucial para la producci\u00f3n agr\u00edcola en Chile, enfrenta riesgos emergentes como sequ\u00edas prolongadas, aumento de plagas y enfermedades, e inundaciones. Estos fen\u00f3menos no solo afectan la producci\u00f3n, sino que tambi\u00e9n aumentan la vulnerabilidad de los peque\u00f1os agricultores y apicultores, quienes desempe\u00f1an un papel clave en la cadena alimentaria. Sin embargo, no se ha explorado lo suficiente c\u00f3mo estos productores enfrentan la situaci\u00f3n actual ni c\u00f3mo adoptan pr\u00e1cticas de inocuidad alimentaria en este contexto. El objetivo general del proyecto es analizar, por primera vez en Chile, c\u00f3mo diversos factores, como el conocimiento, la actitud, el control conductual percibido, y las normas sociales y morales, influyen en la intenci\u00f3n de los agricultores y apicultores de adoptar pr\u00e1cticas de inocuidad alimentaria. Adem\u00e1s, se incorpora un enfoque de g\u00e9nero para evaluar c\u00f3mo hombres y mujeres difieren en sus percepciones y adopci\u00f3n de estas pr\u00e1cticas. Los objetivos espec\u00edficos incluyen: (1) evaluar el impacto conjunto de los mencionados factores en la intenci\u00f3n de adoptar pr\u00e1cticas de inocuidad alimentaria; (2) analizar el efecto moderador del g\u00e9nero en estas relaciones; y (3) realizar talleres participativos para difundir los resultados y fomentar la adopci\u00f3n de estas pr\u00e1cticas.\r\nPara lograr estos objetivos, el proyecto se basa en la Teor\u00eda del Comportamiento Planificado (TPB), la cual ha sido ampliamente utilizada para predecir comportamientos intencionales. Esta teor\u00eda sugiere que la intenci\u00f3n de adoptar un comportamiento est\u00e1 determinada por tres factores principales: actitudes hacia el comportamiento, normas subjetivas y control conductual percibido. En el contexto de este estudio, se explorar\u00e1n tambi\u00e9n las normas morales y el conocimiento como factores adicionales. Adem\u00e1s, se utilizar\u00e1 la metodolog\u00eda de Modelos de Ecuaciones Estructurales (SEM) para analizar la relaci\u00f3n entre estos factores y la intenci\u00f3n de adoptar pr\u00e1cticas seguras en el \u00e1mbito de la agricultura y la apicultura.\r\nEl estudio se desarrollar\u00e1 en la Regi\u00f3n de O'Higgins con peque\u00f1os y medianos agricultores y apicultores. Se espera encuestar al menos a 200 participantes, asegurando que un 50% sean mujeres, lo que permitir\u00e1 analizar las diferencias de g\u00e9nero en la adopci\u00f3n de pr\u00e1cticas de inocuidad alimentaria. Los datos obtenidos a trav\u00e9s de encuestas se someter\u00e1n a un an\u00e1lisis factorial exploratorio para validar los constructos medidos y, posteriormente, se aplicar\u00e1n los SEM para identificar relaciones entre variables y evaluar el impacto del g\u00e9nero en la intenci\u00f3n de adopci\u00f3n.\r\nEl proyecto tambi\u00e9n contempla la realizaci\u00f3n de talleres participativos, donde agricultores y apicultores podr\u00e1n discutir los resultados de la investigaci\u00f3n y explorar soluciones conjuntas para mejorar la adopci\u00f3n de pr\u00e1cticas de inocuidad alimentaria. Estos talleres servir\u00e1n no solo como una v\u00eda para la comunicaci\u00f3n de resultados, sino tambi\u00e9n como un espacio para fomentar la co-creaci\u00f3n de estrategias que puedan ser implementadas de manera efectiva por los productores.\r\nLos impactos esperados del proyecto son significativos tanto a nivel regional como nacional e internacional. En primer lugar, el estudio proporcionar\u00e1 un modelo te\u00f3rico validado sobre la adopci\u00f3n de pr\u00e1cticas de inocuidad alimentaria en el contexto del cambio clim\u00e1tico, lo cual contribuir\u00e1 a la generaci\u00f3n de pol\u00edticas p\u00fablicas y programas de capacitaci\u00f3n para mejorar la resiliencia de los peque\u00f1os productores ante riesgos alimentarios emergentes. Adem\u00e1s, el enfoque de g\u00e9nero permitir\u00e1 identificar y abordar las diferencias entre hombres y mujeres en la adopci\u00f3n de estas pr\u00e1cticas, lo que ayudar\u00e1 a dise\u00f1ar intervenciones m\u00e1s inclusivas y equitativas. A nivel internacional, este proyecto se alinea con los esfuerzos globales para mitigar los impactos del cambio clim\u00e1tico en la inocuidad alimentaria, y los hallazgos contribuir\u00e1n al desarrollo de pol\u00edticas y programas que integren la sostenibilidad en los sistemas agroalimentarios.\r\nFinalmente, este proyecto fortalecer\u00e1 la colaboraci\u00f3n interdisciplinaria entre las investigadoras, permitiendo la apertura de nuevas l\u00edneas de investigaci\u00f3n en inocuidad alimentaria, cambio clim\u00e1tico y equidad de g\u00e9nero, y posicionando a la Universidad de O'Higgins como un referente en estudios sobre la adaptaci\u00f3n al cambio clim\u00e1tico en la agricultura y apicultura.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2024 - Noviembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26426\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Cambio clim\u00e1tico y riesgos alimentarios: Evaluaci\u00f3n con enfoque de g\u00e9nero de los factores que afectan la intenci\u00f3n de adopci\u00f3n de pr\u00e1cticas de inocuidad alimentaria en agricultura y apicultura\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26426\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26426\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto aborda los desaf\u00edos actuales relacionados con la inocuidad alimentaria en la Regi\u00f3n de O'Higgins, particularmente en el contexto de cambio clim\u00e1tico. Esta regi\u00f3n, crucial para la producci\u00f3n agr\u00edcola en Chile, enfrenta riesgos emergentes como sequ\u00edas prolongadas, aumento de plagas y enfermedades, e inundaciones. Estos fen\u00f3menos no solo afectan la producci\u00f3n, sino que tambi\u00e9n aumentan la vulnerabilidad de los peque\u00f1os agricultores y apicultores, quienes desempe\u00f1an un papel clave en la cadena alimentaria. Sin embargo, no se ha explorado lo suficiente c\u00f3mo estos productores enfrentan la situaci\u00f3n actual ni c\u00f3mo adoptan pr\u00e1cticas de inocuidad alimentaria en este contexto. El objetivo general del proyecto es analizar, por primera vez en Chile, c\u00f3mo diversos factores, como el conocimiento, la actitud, el control conductual percibido, y las normas sociales y morales, influyen en la intenci\u00f3n de los agricultores y apicultores de adoptar pr\u00e1cticas de inocuidad alimentaria. Adem\u00e1s, se incorpora un enfoque de g\u00e9nero para evaluar c\u00f3mo hombres y mujeres difieren en sus percepciones y adopci\u00f3n de estas pr\u00e1cticas. Los objetivos espec\u00edficos incluyen: (1) evaluar el impacto conjunto de los mencionados factores en la intenci\u00f3n de adoptar pr\u00e1cticas de inocuidad alimentaria; (2) analizar el efecto moderador del g\u00e9nero en estas relaciones; y (3) realizar talleres participativos para difundir los resultados y fomentar la adopci\u00f3n de estas pr\u00e1cticas.\r\nPara lograr estos objetivos, el proyecto se basa en la Teor\u00eda del Comportamiento Planificado (TPB), la cual ha sido ampliamente utilizada para predecir comportamientos intencionales. Esta teor\u00eda sugiere que la intenci\u00f3n de adoptar un comportamiento est\u00e1 determinada por tres factores principales: actitudes hacia el comportamiento, normas subjetivas y control conductual percibido. En el contexto de este estudio, se explorar\u00e1n tambi\u00e9n las normas morales y el conocimiento como factores adicionales. Adem\u00e1s, se utilizar\u00e1 la metodolog\u00eda de Modelos de Ecuaciones Estructurales (SEM) para analizar la relaci\u00f3n entre estos factores y la intenci\u00f3n de adoptar pr\u00e1cticas seguras en el \u00e1mbito de la agricultura y la apicultura.\r\nEl estudio se desarrollar\u00e1 en la Regi\u00f3n de O'Higgins con peque\u00f1os y medianos agricultores y apicultores. Se espera encuestar al menos a 200 participantes, asegurando que un 50% sean mujeres, lo que permitir\u00e1 analizar las diferencias de g\u00e9nero en la adopci\u00f3n de pr\u00e1cticas de inocuidad alimentaria. Los datos obtenidos a trav\u00e9s de encuestas se someter\u00e1n a un an\u00e1lisis factorial exploratorio para validar los constructos medidos y, posteriormente, se aplicar\u00e1n los SEM para identificar relaciones entre variables y evaluar el impacto del g\u00e9nero en la intenci\u00f3n de adopci\u00f3n.\r\nEl proyecto tambi\u00e9n contempla la realizaci\u00f3n de talleres participativos, donde agricultores y apicultores podr\u00e1n discutir los resultados de la investigaci\u00f3n y explorar soluciones conjuntas para mejorar la adopci\u00f3n de pr\u00e1cticas de inocuidad alimentaria. Estos talleres servir\u00e1n no solo como una v\u00eda para la comunicaci\u00f3n de resultados, sino tambi\u00e9n como un espacio para fomentar la co-creaci\u00f3n de estrategias que puedan ser implementadas de manera efectiva por los productores.\r\nLos impactos esperados del proyecto son significativos tanto a nivel regional como nacional e internacional. En primer lugar, el estudio proporcionar\u00e1 un modelo te\u00f3rico validado sobre la adopci\u00f3n de pr\u00e1cticas de inocuidad alimentaria en el contexto del cambio clim\u00e1tico, lo cual contribuir\u00e1 a la generaci\u00f3n de pol\u00edticas p\u00fablicas y programas de capacitaci\u00f3n para mejorar la resiliencia de los peque\u00f1os productores ante riesgos alimentarios emergentes. Adem\u00e1s, el enfoque de g\u00e9nero permitir\u00e1 identificar y abordar las diferencias entre hombres y mujeres en la adopci\u00f3n de estas pr\u00e1cticas, lo que ayudar\u00e1 a dise\u00f1ar intervenciones m\u00e1s inclusivas y equitativas. A nivel internacional, este proyecto se alinea con los esfuerzos globales para mitigar los impactos del cambio clim\u00e1tico en la inocuidad alimentaria, y los hallazgos contribuir\u00e1n al desarrollo de pol\u00edticas y programas que integren la sostenibilidad en los sistemas agroalimentarios.\r\nFinalmente, este proyecto fortalecer\u00e1 la colaboraci\u00f3n interdisciplinaria entre las investigadoras, permitiendo la apertura de nuevas l\u00edneas de investigaci\u00f3n en inocuidad alimentaria, cambio clim\u00e1tico y equidad de g\u00e9nero, y posicionando a la Universidad de O'Higgins como un referente en estudios sobre la adaptaci\u00f3n al cambio clim\u00e1tico en la agricultura y apicultura.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2024 - Noviembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26643\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Cambio clim\u00e1tico y riesgos alimentarios: Evaluaci\u00f3n con enfoque de g\u00e9nero de los factores que afectan la intenci\u00f3n de adopci\u00f3n de pr\u00e1cticas de inocuidad alimentaria en agricultura y apicultura\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26643\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26643\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto aborda los desaf\u00edos actuales relacionados con la inocuidad alimentaria en la Regi\u00f3n de O'Higgins, particularmente en el contexto de cambio clim\u00e1tico. Esta regi\u00f3n, crucial para la producci\u00f3n agr\u00edcola en Chile, enfrenta riesgos emergentes como sequ\u00edas prolongadas, aumento de plagas y enfermedades, e inundaciones. Estos fen\u00f3menos no solo afectan la producci\u00f3n, sino que tambi\u00e9n aumentan la vulnerabilidad de los peque\u00f1os agricultores y apicultores, quienes desempe\u00f1an un papel clave en la cadena alimentaria. Sin embargo, no se ha explorado lo suficiente c\u00f3mo estos productores enfrentan la situaci\u00f3n actual ni c\u00f3mo adoptan pr\u00e1cticas de inocuidad alimentaria en este contexto. El objetivo general del proyecto es analizar, por primera vez en Chile, c\u00f3mo diversos factores, como el conocimiento, la actitud, el control conductual percibido, y las normas sociales y morales, influyen en la intenci\u00f3n de los agricultores y apicultores de adoptar pr\u00e1cticas de inocuidad alimentaria. Adem\u00e1s, se incorpora un enfoque de g\u00e9nero para evaluar c\u00f3mo hombres y mujeres difieren en sus percepciones y adopci\u00f3n de estas pr\u00e1cticas. Los objetivos espec\u00edficos incluyen: (1) evaluar el impacto conjunto de los mencionados factores en la intenci\u00f3n de adoptar pr\u00e1cticas de inocuidad alimentaria; (2) analizar el efecto moderador del g\u00e9nero en estas relaciones; y (3) realizar talleres participativos para difundir los resultados y fomentar la adopci\u00f3n de estas pr\u00e1cticas.\r\nPara lograr estos objetivos, el proyecto se basa en la Teor\u00eda del Comportamiento Planificado (TPB), la cual ha sido ampliamente utilizada para predecir comportamientos intencionales. Esta teor\u00eda sugiere que la intenci\u00f3n de adoptar un comportamiento est\u00e1 determinada por tres factores principales: actitudes hacia el comportamiento, normas subjetivas y control conductual percibido. En el contexto de este estudio, se explorar\u00e1n tambi\u00e9n las normas morales y el conocimiento como factores adicionales. Adem\u00e1s, se utilizar\u00e1 la metodolog\u00eda de Modelos de Ecuaciones Estructurales (SEM) para analizar la relaci\u00f3n entre estos factores y la intenci\u00f3n de adoptar pr\u00e1cticas seguras en el \u00e1mbito de la agricultura y la apicultura.\r\nEl estudio se desarrollar\u00e1 en la Regi\u00f3n de O'Higgins con peque\u00f1os y medianos agricultores y apicultores. Se espera encuestar al menos a 200 participantes, asegurando que un 50% sean mujeres, lo que permitir\u00e1 analizar las diferencias de g\u00e9nero en la adopci\u00f3n de pr\u00e1cticas de inocuidad alimentaria. Los datos obtenidos a trav\u00e9s de encuestas se someter\u00e1n a un an\u00e1lisis factorial exploratorio para validar los constructos medidos y, posteriormente, se aplicar\u00e1n los SEM para identificar relaciones entre variables y evaluar el impacto del g\u00e9nero en la intenci\u00f3n de adopci\u00f3n.\r\nEl proyecto tambi\u00e9n contempla la realizaci\u00f3n de talleres participativos, donde agricultores y apicultores podr\u00e1n discutir los resultados de la investigaci\u00f3n y explorar soluciones conjuntas para mejorar la adopci\u00f3n de pr\u00e1cticas de inocuidad alimentaria. Estos talleres servir\u00e1n no solo como una v\u00eda para la comunicaci\u00f3n de resultados, sino tambi\u00e9n como un espacio para fomentar la co-creaci\u00f3n de estrategias que puedan ser implementadas de manera efectiva por los productores.\r\nLos impactos esperados del proyecto son significativos tanto a nivel regional como nacional e internacional. En primer lugar, el estudio proporcionar\u00e1 un modelo te\u00f3rico validado sobre la adopci\u00f3n de pr\u00e1cticas de inocuidad alimentaria en el contexto del cambio clim\u00e1tico, lo cual contribuir\u00e1 a la generaci\u00f3n de pol\u00edticas p\u00fablicas y programas de capacitaci\u00f3n para mejorar la resiliencia de los peque\u00f1os productores ante riesgos alimentarios emergentes. Adem\u00e1s, el enfoque de g\u00e9nero permitir\u00e1 identificar y abordar las diferencias entre hombres y mujeres en la adopci\u00f3n de estas pr\u00e1cticas, lo que ayudar\u00e1 a dise\u00f1ar intervenciones m\u00e1s inclusivas y equitativas. A nivel internacional, este proyecto se alinea con los esfuerzos globales para mitigar los impactos del cambio clim\u00e1tico en la inocuidad alimentaria, y los hallazgos contribuir\u00e1n al desarrollo de pol\u00edticas y programas que integren la sostenibilidad en los sistemas agroalimentarios.\r\nFinalmente, este proyecto fortalecer\u00e1 la colaboraci\u00f3n interdisciplinaria entre las investigadoras, permitiendo la apertura de nuevas l\u00edneas de investigaci\u00f3n en inocuidad alimentaria, cambio clim\u00e1tico y equidad de g\u00e9nero, y posicionando a la Universidad de O'Higgins como un referente en estudios sobre la adaptaci\u00f3n al cambio clim\u00e1tico en la agricultura y apicultura.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2024 - Noviembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27063\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Cambio clim\u00e1tico y riesgos alimentarios: Evaluaci\u00f3n con enfoque de g\u00e9nero de los factores que afectan la intenci\u00f3n de adopci\u00f3n de pr\u00e1cticas de inocuidad alimentaria en agricultura y apicultura\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27063\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27063\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto aborda los desaf\u00edos actuales relacionados con la inocuidad alimentaria en la Regi\u00f3n de O'Higgins, particularmente en el contexto de cambio clim\u00e1tico. Esta regi\u00f3n, crucial para la producci\u00f3n agr\u00edcola en Chile, enfrenta riesgos emergentes como sequ\u00edas prolongadas, aumento de plagas y enfermedades, e inundaciones. Estos fen\u00f3menos no solo afectan la producci\u00f3n, sino que tambi\u00e9n aumentan la vulnerabilidad de los peque\u00f1os agricultores y apicultores, quienes desempe\u00f1an un papel clave en la cadena alimentaria. Sin embargo, no se ha explorado lo suficiente c\u00f3mo estos productores enfrentan la situaci\u00f3n actual ni c\u00f3mo adoptan pr\u00e1cticas de inocuidad alimentaria en este contexto. El objetivo general del proyecto es analizar, por primera vez en Chile, c\u00f3mo diversos factores, como el conocimiento, la actitud, el control conductual percibido, y las normas sociales y morales, influyen en la intenci\u00f3n de los agricultores y apicultores de adoptar pr\u00e1cticas de inocuidad alimentaria. Adem\u00e1s, se incorpora un enfoque de g\u00e9nero para evaluar c\u00f3mo hombres y mujeres difieren en sus percepciones y adopci\u00f3n de estas pr\u00e1cticas. Los objetivos espec\u00edficos incluyen: (1) evaluar el impacto conjunto de los mencionados factores en la intenci\u00f3n de adoptar pr\u00e1cticas de inocuidad alimentaria; (2) analizar el efecto moderador del g\u00e9nero en estas relaciones; y (3) realizar talleres participativos para difundir los resultados y fomentar la adopci\u00f3n de estas pr\u00e1cticas.\r\nPara lograr estos objetivos, el proyecto se basa en la Teor\u00eda del Comportamiento Planificado (TPB), la cual ha sido ampliamente utilizada para predecir comportamientos intencionales. Esta teor\u00eda sugiere que la intenci\u00f3n de adoptar un comportamiento est\u00e1 determinada por tres factores principales: actitudes hacia el comportamiento, normas subjetivas y control conductual percibido. En el contexto de este estudio, se explorar\u00e1n tambi\u00e9n las normas morales y el conocimiento como factores adicionales. Adem\u00e1s, se utilizar\u00e1 la metodolog\u00eda de Modelos de Ecuaciones Estructurales (SEM) para analizar la relaci\u00f3n entre estos factores y la intenci\u00f3n de adoptar pr\u00e1cticas seguras en el \u00e1mbito de la agricultura y la apicultura.\r\nEl estudio se desarrollar\u00e1 en la Regi\u00f3n de O'Higgins con peque\u00f1os y medianos agricultores y apicultores. Se espera encuestar al menos a 200 participantes, asegurando que un 50% sean mujeres, lo que permitir\u00e1 analizar las diferencias de g\u00e9nero en la adopci\u00f3n de pr\u00e1cticas de inocuidad alimentaria. Los datos obtenidos a trav\u00e9s de encuestas se someter\u00e1n a un an\u00e1lisis factorial exploratorio para validar los constructos medidos y, posteriormente, se aplicar\u00e1n los SEM para identificar relaciones entre variables y evaluar el impacto del g\u00e9nero en la intenci\u00f3n de adopci\u00f3n.\r\nEl proyecto tambi\u00e9n contempla la realizaci\u00f3n de talleres participativos, donde agricultores y apicultores podr\u00e1n discutir los resultados de la investigaci\u00f3n y explorar soluciones conjuntas para mejorar la adopci\u00f3n de pr\u00e1cticas de inocuidad alimentaria. Estos talleres servir\u00e1n no solo como una v\u00eda para la comunicaci\u00f3n de resultados, sino tambi\u00e9n como un espacio para fomentar la co-creaci\u00f3n de estrategias que puedan ser implementadas de manera efectiva por los productores.\r\nLos impactos esperados del proyecto son significativos tanto a nivel regional como nacional e internacional. En primer lugar, el estudio proporcionar\u00e1 un modelo te\u00f3rico validado sobre la adopci\u00f3n de pr\u00e1cticas de inocuidad alimentaria en el contexto del cambio clim\u00e1tico, lo cual contribuir\u00e1 a la generaci\u00f3n de pol\u00edticas p\u00fablicas y programas de capacitaci\u00f3n para mejorar la resiliencia de los peque\u00f1os productores ante riesgos alimentarios emergentes. Adem\u00e1s, el enfoque de g\u00e9nero permitir\u00e1 identificar y abordar las diferencias entre hombres y mujeres en la adopci\u00f3n de estas pr\u00e1cticas, lo que ayudar\u00e1 a dise\u00f1ar intervenciones m\u00e1s inclusivas y equitativas. A nivel internacional, este proyecto se alinea con los esfuerzos globales para mitigar los impactos del cambio clim\u00e1tico en la inocuidad alimentaria, y los hallazgos contribuir\u00e1n al desarrollo de pol\u00edticas y programas que integren la sostenibilidad en los sistemas agroalimentarios.\r\nFinalmente, este proyecto fortalecer\u00e1 la colaboraci\u00f3n interdisciplinaria entre las investigadoras, permitiendo la apertura de nuevas l\u00edneas de investigaci\u00f3n en inocuidad alimentaria, cambio clim\u00e1tico y equidad de g\u00e9nero, y posicionando a la Universidad de O'Higgins como un referente en estudios sobre la adaptaci\u00f3n al cambio clim\u00e1tico en la agricultura y apicultura.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2024 - Noviembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26719\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Plan de Formaci\u00f3n en Lenguaje Leer para Aprender\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26719\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26719\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El \u0093Plan de Formaci\u00f3n en Lenguaje Leer para Aprender\u0094, tiene como objetivo general\r\ndesarrollar habilidades profesionales y t\u00e9cnicas para el fortalecimiento de la comprensi\u00f3n\r\nlectora en todos los niveles educativos, mediante la aplicaci\u00f3n de estrategias did\u00e1cticas\r\nbasadas en evidencia, adaptadas al contexto chileno y aptas para modalidades\r\neducativas diversas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2024 - Diciembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26181\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Calidad de agua en una cuenca de alta monta\u00f1a afectada por la degradaci\u00f3n de la criosfera\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26181\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26181\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Calidad de agua en una cuenca de alta monta\u00f1a afectada por la degradaci\u00f3n de\r\nla criosfera[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26291\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Micropl\u00e1sticos en material particulado en la Regi\u00f3n de O\u0092Higgins: evaluando su presencia, exposici\u00f3n e interacci\u00f3n con elementos potencialmente t\u00f3xicos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26291\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26291\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Los micropl\u00e1sticos son part\u00edculas de pl\u00e1stico con un tama\u00f1o entre 0.1 &#956;m y 5 mm, los cuales han recibido una amplia atenci\u00f3n debido a sus posibles efectos sobre los organismos vivos, la contaminaci\u00f3n de los ecosistemas, la baja tasa de reciclaje, su f\u00e1cil transporte y su interacci\u00f3n con contaminantes org\u00e1nicos e inorg\u00e1nicos. Los micropl\u00e1sticos son considerados contaminantes emergentes, pues, sus efectos sobre los organismos a\u00fan no han sido totalmente descritos. Sin embargo, se ha demostrado que los diversos aditivos que poseen los pl\u00e1sticos (por ejemplo, bisfenoles, ftalatos, irganox) afectan negativamente a diversos organismos, con potenciales efectos adversos para la salud humana. Por otra parte, a medida que los micropl\u00e1sticos sufren el proceso de envejecimiento o degradaci\u00f3n por efecto de las condiciones ambientales, estos poseen una mayor \u00e1rea superficial y reactividad, lo que promueve su interacci\u00f3n con otros contaminantes inorg\u00e1nicos (por ejemplo, metales pesados) y org\u00e1nicos (por ejemplo, hidrocarburos polic\u00edclicos arom\u00e1ticos). Por lo tanto, los micropl\u00e1sticos poseen diversos riesgos para los organismos que no se conocen a profundidad, lo que requiere un mayor esfuerzo investigativo a nivel mundial.   \r\n\r\nSi bien la problem\u00e1tica de la contaminaci\u00f3n por micropl\u00e1sticos es de conocimiento p\u00fablico, su estudio se ha enfocado en los ecosistemas marinos, espec\u00edficamente en el agua, arena de playa en la l\u00ednea costera y diversos organismos, con poco esfuerzo de muestreo en otras matrices ambientales como los suelos, aguas continentales y la atm\u00f3sfera. Esta \u00faltima es de gran importancia ya que, debido al bajo tama\u00f1o y densidad del micropl\u00e1stico, este puede ser resuspendido en la columna de aire, siendo f\u00e1cilmente transportado desde el suelo a la atm\u00f3sfera y siendo expuestos a los organismos vivos. Es por esto que el material particulado proveniente de eventos de deposici\u00f3n h\u00fameda y seca es considerado como un gran aporte de micropl\u00e1sticos en sistemas terrestres y acu\u00e1ticos, lo que es de gran relevancia cuando se considera la interacci\u00f3n del micropl\u00e1stico con elementos potencialmente t\u00f3xicos como metales u otras mol\u00e9culas org\u00e1nicas. Por lo tanto, la literatura reciente en el \u00e1rea de los micropl\u00e1sticos muestra un incremento en las investigaciones del micropl\u00e1stico atmosf\u00e9rico, pues, es este el que finalmente es inhalado directamente por los seres vivos. \r\n\r\nEn Chile, a pesar de ser el pa\u00eds en Am\u00e9rica Latina que m\u00e1s genera pl\u00e1sticos de un solo uso, y que adem\u00e1s posee comunas ubicadas entre las 10 ciudades m\u00e1s contaminadas de dicha regi\u00f3n, los estudios sobre micropl\u00e1sticos son escasos. Cabe destacar que esta categorizaci\u00f3n est\u00e1 asociada a la calidad del aire, por lo que la presencia del material particulado es un problema significativo. En este contexto, no existen estudios publicados a nivel nacional que eval\u00faen el micropl\u00e1stico atmosf\u00e9rico, por lo que tampoco existe evidencia sobre la interacci\u00f3n entre dicho pl\u00e1stico y otros contaminantes. Esto aplica para la Regi\u00f3n de O\u0092Higgins, la cual, al ser una regi\u00f3n minera y agr\u00edcola, es esperable que presente micropl\u00e1sticos en el material particulado, con la posible interacci\u00f3n con elementos potencialmente t\u00f3xicos, especialmente en los asentamientos con mayor densidad poblacional y desarrollo. Por lo tanto, la presente propuesta busca evaluar la ocurrencia y caracter\u00edsticas de micropl\u00e1sticos presentes en el material particulado en una zona urbana y periurbana de la Regi\u00f3n de O\u0092Higgins, considerando su interacci\u00f3n con elementos potencialmente t\u00f3xicos, la estacionalidad y los eventos de deposici\u00f3n h\u00fameda y seca. Para esto se integrar\u00e1n disciplinas c\u00f3mo el estudio de la meteorolog\u00eda, la qu\u00edmica anal\u00edtica y la contaminaci\u00f3n ambiental. Se colectar\u00e1 y analizar\u00e1 el material particulado de forma mensual cada dos meses durante un a\u00f1o, esto para detectar, cuantificar e identificar los micropl\u00e1sticos presentes debido a eventos de deposici\u00f3n h\u00fameda y seca. Se instalar\u00e1n colectores pasivos de material particulado en las inmediaciones de la Universidad de O\u0092Higgins (Campus Rancagua, Campus Colchagua, Estaci\u00f3n Experimental Choapinos, Chapet\u00f3n). Las part\u00edculas de micropl\u00e1sticos ser\u00e1n analizadas mediante espectroscopia FT-IR\/ATR y\/o con detector FPA. Posterior a la identificaci\u00f3n de los tipos de pol\u00edmeros, las part\u00edculas se analizar\u00e1n con el microscopio de barrido para evaluar la presencia de metales en la superficie del micropl\u00e1stico. Adem\u00e1s, se realizar\u00e1 una extracci\u00f3n con solventes para el an\u00e1lisis de hidrocarburos polic\u00edclicos arom\u00e1ticos y bisfenoles policlorados presentes en el micropl\u00e1stico mediante un GC-MS. Finalmente, se realizar\u00e1n diversos modelos para detectar los mejores predictores meteorol\u00f3gicos y poblacionales para predecir la deposici\u00f3n del micropl\u00e1stico en el material particulado por efecto de la deposici\u00f3n h\u00fameda y seca. Se espera someter un art\u00edculo cient\u00edfico con los resultados de este proyecto para el \u00faltimo a\u00f1o de ejecuci\u00f3n, y adem\u00e1s se busca que este proyecto fortalezca el estudio de los micropl\u00e1sticos en la Universidad de O\u0092Higgins, siendo soporte significativo para futuras postulaciones en equipamiento especializado e investigaciones de gran novedad internacional. Por \u00faltimo, este proyecto sentar\u00e1 las bases para una futura investigaci\u00f3n que eval\u00fae de forma directa e indirecta los efectos del micropl\u00e1stico en la salud humana de las comunidades de la Regi\u00f3n de O\u0092Higgins.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26325\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Micropl\u00e1sticos en material particulado en la Regi\u00f3n de O\u0092Higgins: evaluando su presencia, exposici\u00f3n e interacci\u00f3n con elementos potencialmente t\u00f3xicos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26325\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26325\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Los micropl\u00e1sticos son part\u00edculas de pl\u00e1stico con un tama\u00f1o entre 0.1 &#956;m y 5 mm, los cuales han recibido una amplia atenci\u00f3n debido a sus posibles efectos sobre los organismos vivos, la contaminaci\u00f3n de los ecosistemas, la baja tasa de reciclaje, su f\u00e1cil transporte y su interacci\u00f3n con contaminantes org\u00e1nicos e inorg\u00e1nicos. Los micropl\u00e1sticos son considerados contaminantes emergentes, pues, sus efectos sobre los organismos a\u00fan no han sido totalmente descritos. Sin embargo, se ha demostrado que los diversos aditivos que poseen los pl\u00e1sticos (por ejemplo, bisfenoles, ftalatos, irganox) afectan negativamente a diversos organismos, con potenciales efectos adversos para la salud humana. Por otra parte, a medida que los micropl\u00e1sticos sufren el proceso de envejecimiento o degradaci\u00f3n por efecto de las condiciones ambientales, estos poseen una mayor \u00e1rea superficial y reactividad, lo que promueve su interacci\u00f3n con otros contaminantes inorg\u00e1nicos (por ejemplo, metales pesados) y org\u00e1nicos (por ejemplo, hidrocarburos polic\u00edclicos arom\u00e1ticos). Por lo tanto, los micropl\u00e1sticos poseen diversos riesgos para los organismos que no se conocen a profundidad, lo que requiere un mayor esfuerzo investigativo a nivel mundial.   \r\n\r\nSi bien la problem\u00e1tica de la contaminaci\u00f3n por micropl\u00e1sticos es de conocimiento p\u00fablico, su estudio se ha enfocado en los ecosistemas marinos, espec\u00edficamente en el agua, arena de playa en la l\u00ednea costera y diversos organismos, con poco esfuerzo de muestreo en otras matrices ambientales como los suelos, aguas continentales y la atm\u00f3sfera. Esta \u00faltima es de gran importancia ya que, debido al bajo tama\u00f1o y densidad del micropl\u00e1stico, este puede ser resuspendido en la columna de aire, siendo f\u00e1cilmente transportado desde el suelo a la atm\u00f3sfera y siendo expuestos a los organismos vivos. Es por esto que el material particulado proveniente de eventos de deposici\u00f3n h\u00fameda y seca es considerado como un gran aporte de micropl\u00e1sticos en sistemas terrestres y acu\u00e1ticos, lo que es de gran relevancia cuando se considera la interacci\u00f3n del micropl\u00e1stico con elementos potencialmente t\u00f3xicos como metales u otras mol\u00e9culas org\u00e1nicas. Por lo tanto, la literatura reciente en el \u00e1rea de los micropl\u00e1sticos muestra un incremento en las investigaciones del micropl\u00e1stico atmosf\u00e9rico, pues, es este el que finalmente es inhalado directamente por los seres vivos. \r\n\r\nEn Chile, a pesar de ser el pa\u00eds en Am\u00e9rica Latina que m\u00e1s genera pl\u00e1sticos de un solo uso, y que adem\u00e1s posee comunas ubicadas entre las 10 ciudades m\u00e1s contaminadas de dicha regi\u00f3n, los estudios sobre micropl\u00e1sticos son escasos. Cabe destacar que esta categorizaci\u00f3n est\u00e1 asociada a la calidad del aire, por lo que la presencia del material particulado es un problema significativo. En este contexto, no existen estudios publicados a nivel nacional que eval\u00faen el micropl\u00e1stico atmosf\u00e9rico, por lo que tampoco existe evidencia sobre la interacci\u00f3n entre dicho pl\u00e1stico y otros contaminantes. Esto aplica para la Regi\u00f3n de O\u0092Higgins, la cual, al ser una regi\u00f3n minera y agr\u00edcola, es esperable que presente micropl\u00e1sticos en el material particulado, con la posible interacci\u00f3n con elementos potencialmente t\u00f3xicos, especialmente en los asentamientos con mayor densidad poblacional y desarrollo. Por lo tanto, la presente propuesta busca evaluar la ocurrencia y caracter\u00edsticas de micropl\u00e1sticos presentes en el material particulado en una zona urbana y periurbana de la Regi\u00f3n de O\u0092Higgins, considerando su interacci\u00f3n con elementos potencialmente t\u00f3xicos, la estacionalidad y los eventos de deposici\u00f3n h\u00fameda y seca. Para esto se integrar\u00e1n disciplinas c\u00f3mo el estudio de la meteorolog\u00eda, la qu\u00edmica anal\u00edtica y la contaminaci\u00f3n ambiental. Se colectar\u00e1 y analizar\u00e1 el material particulado de forma mensual cada dos meses durante un a\u00f1o, esto para detectar, cuantificar e identificar los micropl\u00e1sticos presentes debido a eventos de deposici\u00f3n h\u00fameda y seca. Se instalar\u00e1n colectores pasivos de material particulado en las inmediaciones de la Universidad de O\u0092Higgins (Campus Rancagua, Campus Colchagua, Estaci\u00f3n Experimental Choapinos, Chapet\u00f3n). Las part\u00edculas de micropl\u00e1sticos ser\u00e1n analizadas mediante espectroscopia FT-IR\/ATR y\/o con detector FPA. Posterior a la identificaci\u00f3n de los tipos de pol\u00edmeros, las part\u00edculas se analizar\u00e1n con el microscopio de barrido para evaluar la presencia de metales en la superficie del micropl\u00e1stico. Adem\u00e1s, se realizar\u00e1 una extracci\u00f3n con solventes para el an\u00e1lisis de hidrocarburos polic\u00edclicos arom\u00e1ticos y bisfenoles policlorados presentes en el micropl\u00e1stico mediante un GC-MS. Finalmente, se realizar\u00e1n diversos modelos para detectar los mejores predictores meteorol\u00f3gicos y poblacionales para predecir la deposici\u00f3n del micropl\u00e1stico en el material particulado por efecto de la deposici\u00f3n h\u00fameda y seca. Se espera someter un art\u00edculo cient\u00edfico con los resultados de este proyecto para el \u00faltimo a\u00f1o de ejecuci\u00f3n, y adem\u00e1s se busca que este proyecto fortalezca el estudio de los micropl\u00e1sticos en la Universidad de O\u0092Higgins, siendo soporte significativo para futuras postulaciones en equipamiento especializado e investigaciones de gran novedad internacional. Por \u00faltimo, este proyecto sentar\u00e1 las bases para una futura investigaci\u00f3n que eval\u00fae de forma directa e indirecta los efectos del micropl\u00e1stico en la salud humana de las comunidades de la Regi\u00f3n de O\u0092Higgins.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2024 - Julio 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26417\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estr\u00e9s y condiciones laborales en profesores de educaci\u00f3n media: Un enfoque multidisciplinario para el dise\u00f1o de pol\u00edticas p\u00fablicas en la Comuna de Rancagua\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26417\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26417\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El estr\u00e9s docente es un problema creciente en el sistema educativo chileno, con implicaciones significativas para la calidad de la ense\u00f1anza y el bienestar de los educadores. Este proyecto interdisciplinario aborda esta problem\u00e1tica en la educaci\u00f3n secundaria de la Comuna de Rancagua, utilizando un enfoque innovador desde un planteamiento de estudio mixto cuanti-cualitativo. El estudio se centra en la comprensi\u00f3n integral del estr\u00e9s docente, considerando que las transformaciones recientes en el sistema educativo chileno han aumentado las exigencias sobre los profesores. Factores como la mercantilizaci\u00f3n de la educaci\u00f3n, la presi\u00f3n por resultados en pruebas estandarizadas, las condiciones laborales precarias contribuyen a niveles elevados de estr\u00e9s, afectando la calidad educativa y el bienestar docente. A ello se suman presiones administrativas y exigencias que generan agobio laboral (burnout), estr\u00e9s y que se han relacionado con un aumento de la tasa de abandono laboral en el sistema educacional chileno.   \r\n\r\nEl objetivo general del proyecto es analizar la relaci\u00f3n entre marcadores biol\u00f3gicos, psicol\u00f3gicos y las percepciones subjetivas que explican el origen del estr\u00e9s asociado al trabajo docente de profesores de educaci\u00f3n media de la Comuna de Rancagua, con el fin de desarrollar un modelo comprensivo que permita el dise\u00f1o de pol\u00edticas p\u00fablicas orientadas a mejorar las condiciones laborales y el bienestar en este sector educativo. Los objetivos espec\u00edficos incluyen: 1) determinar la prevalencia y severidad del estr\u00e9s en profesores mediante medidas fisiol\u00f3gicas y psicol\u00f3gicas; 2) analizar las principales fuentes de estr\u00e9s percibido por los profesores; 3) correlacionar variables fisiol\u00f3gicas, psicol\u00f3gicas y sociales para desarrollar un modelo te\u00f3rico integrado; y 4) generar recomendaciones basadas en evidencia para el dise\u00f1o de intervenciones y pol\u00edticas p\u00fablicas. \r\n\r\nLa metodolog\u00eda del estudio emplea un dise\u00f1o mixto de corte transversal, con una muestra de 100 profesores de educaci\u00f3n media de Rancagua. Se utilizar\u00e1 un muestreo estratificado proporcional considerando caracter\u00edsticas socioecon\u00f3micas del colegio, tipo de financiamiento, proyecto educativo, y otros factores relevantes. La innovaci\u00f3n metodol\u00f3gica clave es la medici\u00f3n de cortisol en u\u00f1as como biomarcador de estr\u00e9s cr\u00f3nico, ofreciendo ventajas significativas sobre m\u00e9todos tradicionales como el an\u00e1lisis de pelo. Esta t\u00e9cnica proporciona una medida menos invasiva, m\u00e1s accesible y potencialmente m\u00e1s estable del estr\u00e9s a largo plazo. Adem\u00e1s de la medici\u00f3n de cortisol, el estudio incluir\u00e1 evaluaciones psicol\u00f3gicas utilizando instrumentos validados como la Escala de Estr\u00e9s Percibido (PSS-14), DAAS-21 para depresi\u00f3n y ansiedad, y el Inventario de Burnout de Maslach (MBI-ES). Se realizar\u00e1n entrevistas en profundidad con 40 profesores para comprender las fuentes de estr\u00e9s y el contexto laboral. El an\u00e1lisis de datos incluir\u00e1 modelos de regresi\u00f3n multilineal y an\u00e1lisis de componentes principales para correlacionar las variables fisiol\u00f3gicas, psicol\u00f3gicas y sociales. \r\n\r\nEl proyecto se destaca por su enfoque interdisciplinario, integrando experticias en neurociencias, psicolog\u00eda, pol\u00edticas educativas y metodolog\u00eda cualitativa. El equipo de investigaci\u00f3n incluye al Dr. Gonzalo Terreros, la Dra. Camila Oda, la Dra. Ngaire Honey, el Dr. Felipe Mu\u00f1oz y la Dra(c). Cecilia Cort\u00e9s Rojas. Esta colaboraci\u00f3n permite un an\u00e1lisis hol\u00edstico del fen\u00f3meno del estr\u00e9s docente, desde su manifestaci\u00f3n biol\u00f3gica hasta sus implicaciones en las pol\u00edticas educativas.Se espera que los resultados de este estudio proporcionen hallazgos valiosos para el dise\u00f1o de intervenciones y pol\u00edticas que aborden efectivamente el estr\u00e9s docente.  \r\n\r\nEl proyecto tiene el potencial de influir significativamente en la formulaci\u00f3n de pol\u00edticas educativas, mejorando las condiciones laborales de los docentes y fortaleciendo el sistema educativo chileno en su conjunto. La implementaci\u00f3n pionera de la medici\u00f3n de cortisol en u\u00f1as posiciona este estudio a la vanguardia de la investigaci\u00f3n sobre estr\u00e9s docente, ofreciendo una nueva perspectiva sobre este importante problema educativo. \r\n\r\nAdem\u00e1s de su contribuci\u00f3n al conocimiento cient\u00edfico, este estudio tiene implicaciones pr\u00e1cticas directas para la mejora de la calidad educativa en Chile. Los resultados podr\u00edan informar el dise\u00f1o de programas de prevenci\u00f3n y manejo del estr\u00e9s para docentes, as\u00ed como reformas en las pol\u00edticas educativas que aborden las causas estructurales del estr\u00e9s en el sistema escolar. El proyecto tambi\u00e9n contribuye a la formaci\u00f3n de nuevos investigadores, incluyendo estudiantes de pregrado que participar\u00e1n en diversas etapas de la investigaci\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2024 - Octubre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26502\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Violencia econ\u00f3mica y g\u00e9nero: Significados, experiencias y consecuencias para mujeres en el contexto de relaciones de pareja\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26502\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26502\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La conceptualizaci\u00f3n de la violencia es compleja debido a su amplitud y la diversidad de situaciones a las que se asocia. A menudo, se utiliza un adjetivo espec\u00edfico (como \"pol\u00edtica\", \"de g\u00e9nero\", \"familiar\", entre otros) para precisar el tipo de violencia, lo que ha dado lugar a una gran variedad de enfoques te\u00f3ricos y emp\u00edricos. Pese a la multiplicidad de tipos de violencia, todos comparten ciertos atributos: la violencia es una fuerza din\u00e1mica que atraviesa todas las interacciones sociales, manifest\u00e1ndose tanto de manera visible como invisible. En este sentido, es posible describir la violencia visible como la violencia directa (actos identificables) y la violencia invisible como la estructural (generada por estructuras que niegan necesidades b\u00e1sicas) y la cultural (que legitima la violencia).\r\n\r\nLa violencia de g\u00e9nero ilustra esta imbricaci\u00f3n de formas de violencia visibles e invisibles, afectando especialmente a las mujeres debido a las desigualdades socioculturales y patriarcales existentes en las sociedades actuales. Esta violencia se puede manifestar de diversas maneras: violencia psicol\u00f3gica, f\u00edsica, sexual y econ\u00f3mica, entre otras. En Am\u00e9rica Latina y el Caribe, la violencia contra la mujer es particularmente preocupante, y muchas veces ocurre dentro del hogar y es ejercida por parejas o ex-parejas, espacios tradicionalmente considerados seguros pero que pueden volverse lugares de abuso.\r\n\r\nLa violencia econ\u00f3mica hacia las mujeres es un tipo de violencia menos estudiado, especialmente en Chile. Este tipo de violencia se define como el control sobre la capacidad de una mujer para acceder y gestionar recursos financieros, lo cual perpet\u00faa su dependencia y limita su autonom\u00eda en relaci\u00f3n a su pareja o ex-pareja. Este tipo de violencia se manifiesta mediante la restricci\u00f3n de ingresos, la prohibici\u00f3n de trabajar, la explotaci\u00f3n financiera, la destrucci\u00f3n de bienes personales, entre otras formas. Aunque no siempre es reconocida por las v\u00edctimas, sus efectos pueden ser tan graves como los de otras formas de violencia.\r\n\r\nDe este modo, considerando el escaso conocimiento sobre la violencia econ\u00f3mica, este proyecto busca contribuir a su estudio mediante el estudio de los significados y vivencias que mujeres chilenas mayores de 18 a\u00f1os tienen de este fen\u00f3meno, explorando adem\u00e1s sus percepciones y consecuencias. \r\n\r\nPara eso, realizaremos dos estudios, los cu\u00e1les se enmarcan en un dise\u00f1o mixto de car\u00e1cter secuencial exploratorio para profundizar en las dimensiones de este fen\u00f3meno, sus significados y las vivencias de mujeres chilenas de este tipo de violencia y las consecuencias que esta implica en sus vidas. Adem\u00e1s, se busca generar y sistematizar evidencia de las relaciones entre este tipo de violencia y otros tipos de violencia que afectan a las mujeres, bien como identificar y caracterizar factores protectores y de riesgo que las mujeres puedan tener y\/o disponer en relaci\u00f3n a la violencia econ\u00f3mica en relaciones de pareja.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2024 - Octubre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26703\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            FOVI Comprendiendo la relevancia del juego en  educaci\u00f3n  parvularia\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26703\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26703\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Articular una Red acad\u00e9mica internacional y multidisciplinaria que potencie la investigaci\u00f3n, la innovaci\u00f3n y la formaci\u00f3n de capital humano avanzado para la utilizaci\u00f3n del juego en educaci\u00f3n parvularia y sus alcances pedag\u00f3gicos, con foco particular en la identificaci\u00f3n de oportunidades y desaf\u00edos para su utilizaci\u00f3n adecuada en distintos contextos nacionales y culturales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2024 - Octubre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26761\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Violencia econ\u00f3mica y g\u00e9nero: Significados, experiencias y consecuencias para mujeres en el contexto de relaciones de pareja\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26761\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26761\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La conceptualizaci\u00f3n de la violencia es compleja debido a su amplitud y la diversidad de situaciones a las que se asocia. A menudo, se utiliza un adjetivo espec\u00edfico (como \"pol\u00edtica\", \"de g\u00e9nero\", \"familiar\", entre otros) para precisar el tipo de violencia, lo que ha dado lugar a una gran variedad de enfoques te\u00f3ricos y emp\u00edricos. Pese a la multiplicidad de tipos de violencia, todos comparten ciertos atributos: la violencia es una fuerza din\u00e1mica que atraviesa todas las interacciones sociales, manifest\u00e1ndose tanto de manera visible como invisible. En este sentido, es posible describir la violencia visible como la violencia directa (actos identificables) y la violencia invisible como la estructural (generada por estructuras que niegan necesidades b\u00e1sicas) y la cultural (que legitima la violencia).\r\n\r\nLa violencia de g\u00e9nero ilustra esta imbricaci\u00f3n de formas de violencia visibles e invisibles, afectando especialmente a las mujeres debido a las desigualdades socioculturales y patriarcales existentes en las sociedades actuales. Esta violencia se puede manifestar de diversas maneras: violencia psicol\u00f3gica, f\u00edsica, sexual y econ\u00f3mica, entre otras. En Am\u00e9rica Latina y el Caribe, la violencia contra la mujer es particularmente preocupante, y muchas veces ocurre dentro del hogar y es ejercida por parejas o ex-parejas, espacios tradicionalmente considerados seguros pero que pueden volverse lugares de abuso.\r\n\r\nLa violencia econ\u00f3mica hacia las mujeres es un tipo de violencia menos estudiado, especialmente en Chile. Este tipo de violencia se define como el control sobre la capacidad de una mujer para acceder y gestionar recursos financieros, lo cual perpet\u00faa su dependencia y limita su autonom\u00eda en relaci\u00f3n a su pareja o ex-pareja. Este tipo de violencia se manifiesta mediante la restricci\u00f3n de ingresos, la prohibici\u00f3n de trabajar, la explotaci\u00f3n financiera, la destrucci\u00f3n de bienes personales, entre otras formas. Aunque no siempre es reconocida por las v\u00edctimas, sus efectos pueden ser tan graves como los de otras formas de violencia.\r\n\r\nDe este modo, considerando el escaso conocimiento sobre la violencia econ\u00f3mica, este proyecto busca contribuir a su estudio mediante el estudio de los significados y vivencias que mujeres chilenas mayores de 18 a\u00f1os tienen de este fen\u00f3meno, explorando adem\u00e1s sus percepciones y consecuencias. \r\n\r\nPara eso, realizaremos dos estudios, los cu\u00e1les se enmarcan en un dise\u00f1o mixto de car\u00e1cter secuencial exploratorio para profundizar en las dimensiones de este fen\u00f3meno, sus significados y las vivencias de mujeres chilenas de este tipo de violencia y las consecuencias que esta implica en sus vidas. Adem\u00e1s, se busca generar y sistematizar evidencia de las relaciones entre este tipo de violencia y otros tipos de violencia que afectan a las mujeres, bien como identificar y caracterizar factores protectores y de riesgo que las mujeres puedan tener y\/o disponer en relaci\u00f3n a la violencia econ\u00f3mica en relaciones de pareja.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26777\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Micropl\u00e1sticos en material particulado en la Regi\u00f3n de O\u0092Higgins: evaluando su presencia, exposici\u00f3n e interacci\u00f3n con elementos potencialmente t\u00f3xicos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26777\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26777\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Los micropl\u00e1sticos son part\u00edculas de pl\u00e1stico con un tama\u00f1o entre 0.1 &#956;m y 5 mm, los cuales han recibido una amplia atenci\u00f3n debido a sus posibles efectos sobre los organismos vivos, la contaminaci\u00f3n de los ecosistemas, la baja tasa de reciclaje, su f\u00e1cil transporte y su interacci\u00f3n con contaminantes org\u00e1nicos e inorg\u00e1nicos. Los micropl\u00e1sticos son considerados contaminantes emergentes, pues, sus efectos sobre los organismos a\u00fan no han sido totalmente descritos. Sin embargo, se ha demostrado que los diversos aditivos que poseen los pl\u00e1sticos (por ejemplo, bisfenoles, ftalatos, irganox) afectan negativamente a diversos organismos, con potenciales efectos adversos para la salud humana. Por otra parte, a medida que los micropl\u00e1sticos sufren el proceso de envejecimiento o degradaci\u00f3n por efecto de las condiciones ambientales, estos poseen una mayor \u00e1rea superficial y reactividad, lo que promueve su interacci\u00f3n con otros contaminantes inorg\u00e1nicos (por ejemplo, metales pesados) y org\u00e1nicos (por ejemplo, hidrocarburos polic\u00edclicos arom\u00e1ticos). Por lo tanto, los micropl\u00e1sticos poseen diversos riesgos para los organismos que no se conocen a profundidad, lo que requiere un mayor esfuerzo investigativo a nivel mundial.   \r\n\r\nSi bien la problem\u00e1tica de la contaminaci\u00f3n por micropl\u00e1sticos es de conocimiento p\u00fablico, su estudio se ha enfocado en los ecosistemas marinos, espec\u00edficamente en el agua, arena de playa en la l\u00ednea costera y diversos organismos, con poco esfuerzo de muestreo en otras matrices ambientales como los suelos, aguas continentales y la atm\u00f3sfera. Esta \u00faltima es de gran importancia ya que, debido al bajo tama\u00f1o y densidad del micropl\u00e1stico, este puede ser resuspendido en la columna de aire, siendo f\u00e1cilmente transportado desde el suelo a la atm\u00f3sfera y siendo expuestos a los organismos vivos. Es por esto que el material particulado proveniente de eventos de deposici\u00f3n h\u00fameda y seca es considerado como un gran aporte de micropl\u00e1sticos en sistemas terrestres y acu\u00e1ticos, lo que es de gran relevancia cuando se considera la interacci\u00f3n del micropl\u00e1stico con elementos potencialmente t\u00f3xicos como metales u otras mol\u00e9culas org\u00e1nicas. Por lo tanto, la literatura reciente en el \u00e1rea de los micropl\u00e1sticos muestra un incremento en las investigaciones del micropl\u00e1stico atmosf\u00e9rico, pues, es este el que finalmente es inhalado directamente por los seres vivos. \r\n\r\nEn Chile, a pesar de ser el pa\u00eds en Am\u00e9rica Latina que m\u00e1s genera pl\u00e1sticos de un solo uso, y que adem\u00e1s posee comunas ubicadas entre las 10 ciudades m\u00e1s contaminadas de dicha regi\u00f3n, los estudios sobre micropl\u00e1sticos son escasos. Cabe destacar que esta categorizaci\u00f3n est\u00e1 asociada a la calidad del aire, por lo que la presencia del material particulado es un problema significativo. En este contexto, no existen estudios publicados a nivel nacional que eval\u00faen el micropl\u00e1stico atmosf\u00e9rico, por lo que tampoco existe evidencia sobre la interacci\u00f3n entre dicho pl\u00e1stico y otros contaminantes. Esto aplica para la Regi\u00f3n de O\u0092Higgins, la cual, al ser una regi\u00f3n minera y agr\u00edcola, es esperable que presente micropl\u00e1sticos en el material particulado, con la posible interacci\u00f3n con elementos potencialmente t\u00f3xicos, especialmente en los asentamientos con mayor densidad poblacional y desarrollo. Por lo tanto, la presente propuesta busca evaluar la ocurrencia y caracter\u00edsticas de micropl\u00e1sticos presentes en el material particulado en una zona urbana y periurbana de la Regi\u00f3n de O\u0092Higgins, considerando su interacci\u00f3n con elementos potencialmente t\u00f3xicos, la estacionalidad y los eventos de deposici\u00f3n h\u00fameda y seca. Para esto se integrar\u00e1n disciplinas c\u00f3mo el estudio de la meteorolog\u00eda, la qu\u00edmica anal\u00edtica y la contaminaci\u00f3n ambiental. Se colectar\u00e1 y analizar\u00e1 el material particulado de forma mensual cada dos meses durante un a\u00f1o, esto para detectar, cuantificar e identificar los micropl\u00e1sticos presentes debido a eventos de deposici\u00f3n h\u00fameda y seca. Se instalar\u00e1n colectores pasivos de material particulado en las inmediaciones de la Universidad de O\u0092Higgins (Campus Rancagua, Campus Colchagua, Estaci\u00f3n Experimental Choapinos, Chapet\u00f3n). Las part\u00edculas de micropl\u00e1sticos ser\u00e1n analizadas mediante espectroscopia FT-IR\/ATR y\/o con detector FPA. Posterior a la identificaci\u00f3n de los tipos de pol\u00edmeros, las part\u00edculas se analizar\u00e1n con el microscopio de barrido para evaluar la presencia de metales en la superficie del micropl\u00e1stico. Adem\u00e1s, se realizar\u00e1 una extracci\u00f3n con solventes para el an\u00e1lisis de hidrocarburos polic\u00edclicos arom\u00e1ticos y bisfenoles policlorados presentes en el micropl\u00e1stico mediante un GC-MS. Finalmente, se realizar\u00e1n diversos modelos para detectar los mejores predictores meteorol\u00f3gicos y poblacionales para predecir la deposici\u00f3n del micropl\u00e1stico en el material particulado por efecto de la deposici\u00f3n h\u00fameda y seca. Se espera someter un art\u00edculo cient\u00edfico con los resultados de este proyecto para el \u00faltimo a\u00f1o de ejecuci\u00f3n, y adem\u00e1s se busca que este proyecto fortalezca el estudio de los micropl\u00e1sticos en la Universidad de O\u0092Higgins, siendo soporte significativo para futuras postulaciones en equipamiento especializado e investigaciones de gran novedad internacional. Por \u00faltimo, este proyecto sentar\u00e1 las bases para una futura investigaci\u00f3n que eval\u00fae de forma directa e indirecta los efectos del micropl\u00e1stico en la salud humana de las comunidades de la Regi\u00f3n de O\u0092Higgins.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2024 - Diciembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26907\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Calidad de agua en una cuenca de alta monta\u00f1a afectada por la degradaci\u00f3n de la criosfera\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26907\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26907\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Calidad de agua en una cuenca de alta monta\u00f1a afectada por la degradaci\u00f3n de\r\nla criosfera[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2024 - Octubre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26918\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Violencia econ\u00f3mica y g\u00e9nero: Significados, experiencias y consecuencias para mujeres en el contexto de relaciones de pareja\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26918\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26918\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La conceptualizaci\u00f3n de la violencia es compleja debido a su amplitud y la diversidad de situaciones a las que se asocia. A menudo, se utiliza un adjetivo espec\u00edfico (como \"pol\u00edtica\", \"de g\u00e9nero\", \"familiar\", entre otros) para precisar el tipo de violencia, lo que ha dado lugar a una gran variedad de enfoques te\u00f3ricos y emp\u00edricos. Pese a la multiplicidad de tipos de violencia, todos comparten ciertos atributos: la violencia es una fuerza din\u00e1mica que atraviesa todas las interacciones sociales, manifest\u00e1ndose tanto de manera visible como invisible. En este sentido, es posible describir la violencia visible como la violencia directa (actos identificables) y la violencia invisible como la estructural (generada por estructuras que niegan necesidades b\u00e1sicas) y la cultural (que legitima la violencia).\r\n\r\nLa violencia de g\u00e9nero ilustra esta imbricaci\u00f3n de formas de violencia visibles e invisibles, afectando especialmente a las mujeres debido a las desigualdades socioculturales y patriarcales existentes en las sociedades actuales. Esta violencia se puede manifestar de diversas maneras: violencia psicol\u00f3gica, f\u00edsica, sexual y econ\u00f3mica, entre otras. En Am\u00e9rica Latina y el Caribe, la violencia contra la mujer es particularmente preocupante, y muchas veces ocurre dentro del hogar y es ejercida por parejas o ex-parejas, espacios tradicionalmente considerados seguros pero que pueden volverse lugares de abuso.\r\n\r\nLa violencia econ\u00f3mica hacia las mujeres es un tipo de violencia menos estudiado, especialmente en Chile. Este tipo de violencia se define como el control sobre la capacidad de una mujer para acceder y gestionar recursos financieros, lo cual perpet\u00faa su dependencia y limita su autonom\u00eda en relaci\u00f3n a su pareja o ex-pareja. Este tipo de violencia se manifiesta mediante la restricci\u00f3n de ingresos, la prohibici\u00f3n de trabajar, la explotaci\u00f3n financiera, la destrucci\u00f3n de bienes personales, entre otras formas. Aunque no siempre es reconocida por las v\u00edctimas, sus efectos pueden ser tan graves como los de otras formas de violencia.\r\n\r\nDe este modo, considerando el escaso conocimiento sobre la violencia econ\u00f3mica, este proyecto busca contribuir a su estudio mediante el estudio de los significados y vivencias que mujeres chilenas mayores de 18 a\u00f1os tienen de este fen\u00f3meno, explorando adem\u00e1s sus percepciones y consecuencias. \r\n\r\nPara eso, realizaremos dos estudios, los cu\u00e1les se enmarcan en un dise\u00f1o mixto de car\u00e1cter secuencial exploratorio para profundizar en las dimensiones de este fen\u00f3meno, sus significados y las vivencias de mujeres chilenas de este tipo de violencia y las consecuencias que esta implica en sus vidas. Adem\u00e1s, se busca generar y sistematizar evidencia de las relaciones entre este tipo de violencia y otros tipos de violencia que afectan a las mujeres, bien como identificar y caracterizar factores protectores y de riesgo que las mujeres puedan tener y\/o disponer en relaci\u00f3n a la violencia econ\u00f3mica en relaciones de pareja.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2024 - Julio 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26961\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estr\u00e9s y condiciones laborales en profesores de educaci\u00f3n media: Un enfoque multidisciplinario para el dise\u00f1o de pol\u00edticas p\u00fablicas en la Comuna de Rancagua\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26961\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26961\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El estr\u00e9s docente es un problema creciente en el sistema educativo chileno, con implicaciones significativas para la calidad de la ense\u00f1anza y el bienestar de los educadores. Este proyecto interdisciplinario aborda esta problem\u00e1tica en la educaci\u00f3n secundaria de la Comuna de Rancagua, utilizando un enfoque innovador desde un planteamiento de estudio mixto cuanti-cualitativo. El estudio se centra en la comprensi\u00f3n integral del estr\u00e9s docente, considerando que las transformaciones recientes en el sistema educativo chileno han aumentado las exigencias sobre los profesores. Factores como la mercantilizaci\u00f3n de la educaci\u00f3n, la presi\u00f3n por resultados en pruebas estandarizadas, las condiciones laborales precarias contribuyen a niveles elevados de estr\u00e9s, afectando la calidad educativa y el bienestar docente. A ello se suman presiones administrativas y exigencias que generan agobio laboral (burnout), estr\u00e9s y que se han relacionado con un aumento de la tasa de abandono laboral en el sistema educacional chileno.   \r\n\r\nEl objetivo general del proyecto es analizar la relaci\u00f3n entre marcadores biol\u00f3gicos, psicol\u00f3gicos y las percepciones subjetivas que explican el origen del estr\u00e9s asociado al trabajo docente de profesores de educaci\u00f3n media de la Comuna de Rancagua, con el fin de desarrollar un modelo comprensivo que permita el dise\u00f1o de pol\u00edticas p\u00fablicas orientadas a mejorar las condiciones laborales y el bienestar en este sector educativo. Los objetivos espec\u00edficos incluyen: 1) determinar la prevalencia y severidad del estr\u00e9s en profesores mediante medidas fisiol\u00f3gicas y psicol\u00f3gicas; 2) analizar las principales fuentes de estr\u00e9s percibido por los profesores; 3) correlacionar variables fisiol\u00f3gicas, psicol\u00f3gicas y sociales para desarrollar un modelo te\u00f3rico integrado; y 4) generar recomendaciones basadas en evidencia para el dise\u00f1o de intervenciones y pol\u00edticas p\u00fablicas. \r\n\r\nLa metodolog\u00eda del estudio emplea un dise\u00f1o mixto de corte transversal, con una muestra de 100 profesores de educaci\u00f3n media de Rancagua. Se utilizar\u00e1 un muestreo estratificado proporcional considerando caracter\u00edsticas socioecon\u00f3micas del colegio, tipo de financiamiento, proyecto educativo, y otros factores relevantes. La innovaci\u00f3n metodol\u00f3gica clave es la medici\u00f3n de cortisol en u\u00f1as como biomarcador de estr\u00e9s cr\u00f3nico, ofreciendo ventajas significativas sobre m\u00e9todos tradicionales como el an\u00e1lisis de pelo. Esta t\u00e9cnica proporciona una medida menos invasiva, m\u00e1s accesible y potencialmente m\u00e1s estable del estr\u00e9s a largo plazo. Adem\u00e1s de la medici\u00f3n de cortisol, el estudio incluir\u00e1 evaluaciones psicol\u00f3gicas utilizando instrumentos validados como la Escala de Estr\u00e9s Percibido (PSS-14), DAAS-21 para depresi\u00f3n y ansiedad, y el Inventario de Burnout de Maslach (MBI-ES). Se realizar\u00e1n entrevistas en profundidad con 40 profesores para comprender las fuentes de estr\u00e9s y el contexto laboral. El an\u00e1lisis de datos incluir\u00e1 modelos de regresi\u00f3n multilineal y an\u00e1lisis de componentes principales para correlacionar las variables fisiol\u00f3gicas, psicol\u00f3gicas y sociales. \r\n\r\nEl proyecto se destaca por su enfoque interdisciplinario, integrando experticias en neurociencias, psicolog\u00eda, pol\u00edticas educativas y metodolog\u00eda cualitativa. El equipo de investigaci\u00f3n incluye al Dr. Gonzalo Terreros, la Dra. Camila Oda, la Dra. Ngaire Honey, el Dr. Felipe Mu\u00f1oz y la Dra(c). Cecilia Cort\u00e9s Rojas. Esta colaboraci\u00f3n permite un an\u00e1lisis hol\u00edstico del fen\u00f3meno del estr\u00e9s docente, desde su manifestaci\u00f3n biol\u00f3gica hasta sus implicaciones en las pol\u00edticas educativas.Se espera que los resultados de este estudio proporcionen hallazgos valiosos para el dise\u00f1o de intervenciones y pol\u00edticas que aborden efectivamente el estr\u00e9s docente.  \r\n\r\nEl proyecto tiene el potencial de influir significativamente en la formulaci\u00f3n de pol\u00edticas educativas, mejorando las condiciones laborales de los docentes y fortaleciendo el sistema educativo chileno en su conjunto. La implementaci\u00f3n pionera de la medici\u00f3n de cortisol en u\u00f1as posiciona este estudio a la vanguardia de la investigaci\u00f3n sobre estr\u00e9s docente, ofreciendo una nueva perspectiva sobre este importante problema educativo. \r\n\r\nAdem\u00e1s de su contribuci\u00f3n al conocimiento cient\u00edfico, este estudio tiene implicaciones pr\u00e1cticas directas para la mejora de la calidad educativa en Chile. Los resultados podr\u00edan informar el dise\u00f1o de programas de prevenci\u00f3n y manejo del estr\u00e9s para docentes, as\u00ed como reformas en las pol\u00edticas educativas que aborden las causas estructurales del estr\u00e9s en el sistema escolar. El proyecto tambi\u00e9n contribuye a la formaci\u00f3n de nuevos investigadores, incluyendo estudiantes de pregrado que participar\u00e1n en diversas etapas de la investigaci\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2024 - Octubre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26991\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Violencia econ\u00f3mica y g\u00e9nero: Significados, experiencias y consecuencias para mujeres en el contexto de relaciones de pareja\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26991\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26991\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La conceptualizaci\u00f3n de la violencia es compleja debido a su amplitud y la diversidad de situaciones a las que se asocia. A menudo, se utiliza un adjetivo espec\u00edfico (como \"pol\u00edtica\", \"de g\u00e9nero\", \"familiar\", entre otros) para precisar el tipo de violencia, lo que ha dado lugar a una gran variedad de enfoques te\u00f3ricos y emp\u00edricos. Pese a la multiplicidad de tipos de violencia, todos comparten ciertos atributos: la violencia es una fuerza din\u00e1mica que atraviesa todas las interacciones sociales, manifest\u00e1ndose tanto de manera visible como invisible. En este sentido, es posible describir la violencia visible como la violencia directa (actos identificables) y la violencia invisible como la estructural (generada por estructuras que niegan necesidades b\u00e1sicas) y la cultural (que legitima la violencia).\r\n\r\nLa violencia de g\u00e9nero ilustra esta imbricaci\u00f3n de formas de violencia visibles e invisibles, afectando especialmente a las mujeres debido a las desigualdades socioculturales y patriarcales existentes en las sociedades actuales. Esta violencia se puede manifestar de diversas maneras: violencia psicol\u00f3gica, f\u00edsica, sexual y econ\u00f3mica, entre otras. En Am\u00e9rica Latina y el Caribe, la violencia contra la mujer es particularmente preocupante, y muchas veces ocurre dentro del hogar y es ejercida por parejas o ex-parejas, espacios tradicionalmente considerados seguros pero que pueden volverse lugares de abuso.\r\n\r\nLa violencia econ\u00f3mica hacia las mujeres es un tipo de violencia menos estudiado, especialmente en Chile. Este tipo de violencia se define como el control sobre la capacidad de una mujer para acceder y gestionar recursos financieros, lo cual perpet\u00faa su dependencia y limita su autonom\u00eda en relaci\u00f3n a su pareja o ex-pareja. Este tipo de violencia se manifiesta mediante la restricci\u00f3n de ingresos, la prohibici\u00f3n de trabajar, la explotaci\u00f3n financiera, la destrucci\u00f3n de bienes personales, entre otras formas. Aunque no siempre es reconocida por las v\u00edctimas, sus efectos pueden ser tan graves como los de otras formas de violencia.\r\n\r\nDe este modo, considerando el escaso conocimiento sobre la violencia econ\u00f3mica, este proyecto busca contribuir a su estudio mediante el estudio de los significados y vivencias que mujeres chilenas mayores de 18 a\u00f1os tienen de este fen\u00f3meno, explorando adem\u00e1s sus percepciones y consecuencias. \r\n\r\nPara eso, realizaremos dos estudios, los cu\u00e1les se enmarcan en un dise\u00f1o mixto de car\u00e1cter secuencial exploratorio para profundizar en las dimensiones de este fen\u00f3meno, sus significados y las vivencias de mujeres chilenas de este tipo de violencia y las consecuencias que esta implica en sus vidas. Adem\u00e1s, se busca generar y sistematizar evidencia de las relaciones entre este tipo de violencia y otros tipos de violencia que afectan a las mujeres, bien como identificar y caracterizar factores protectores y de riesgo que las mujeres puedan tener y\/o disponer en relaci\u00f3n a la violencia econ\u00f3mica en relaciones de pareja.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> PID2023-146722OB-C21<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2024 - Octubre 2028<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno de espa\u00f1a<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26240\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desvelando las causas del bajo crecimiento en lechones como base para nuevas estrategias de manejo alimentario dirigidas a reducir la variabilidad de los lotes.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26240\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26240\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Estudio de las variables mas relevantes que generan diferencias productivas en lechones desde el nacimiento al destete en sistemas de producci\u00f3n intensiva[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI240013<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26461\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Colaboraci\u00f3n internacional e interdisciplinaria para el estudio de riesgos de intrusi\u00f3n salina inducida por el cambio clim\u00e1tico en ecosistemas agr\u00edcolas costeros y sus efectos en servicios ecosist\u00e9micos de suelos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26461\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26461\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]la presente propuesta tiene como objetivo crear una red internacional\r\nentre la Universidad de O\u0092Higgins, la Universidad de Chile y la Universidad de Maryland, con\r\nun enfoque interdisciplinar, es decir integrando las disciplinas de las ciencias agron\u00f3micas,\r\nciencias naturales y las ciencias sociales para abordar desaf\u00edos relacionados con la\r\nadaptaci\u00f3n de los sistemas agr\u00edcolas costeros y servicios ecosist\u00e9micos de suelos a los\r\nefectos de la intrusi\u00f3n marina. La red de colaboraci\u00f3n, a desplegar en Pichilemu y Maull\u00edn,\r\npermitir\u00e1 robustecer y abordar esta tem\u00e1tica en Chile, y as\u00ed contribuir al desarrollo de\r\nsoluciones en la materia con alcances a nivel nacional.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI240094<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26994\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estudios socio-jur\u00eddicos: ampliando los horizontes de los estudios del Derecho para satisfacer las necesidades profesionales en sociedades complejas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26994\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26994\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto FOVI 240094 tiene como objetivo fortalecer la investigaci\u00f3n y ense\u00f1anza sociojur\u00eddica interdisciplinaria en Chile, con un \u00e9nfasis particular en el desarrollo de capacidades en las universidades regionales del pa\u00eds. Para alcanzar este prop\u00f3sito, el proyecto busca establecer una red internacional de investigaci\u00f3n y ense\u00f1anza socio-legal, conectando a las universidades regionales de Chile con centros internacionales de excelencia, como los de las universidades de Oxford y Cardiff. La Universidad de O\u0092Higgins, a trav\u00e9s de su Instituto de Ciencias Sociales, act\u00faa como el nodo central de esta red.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> EXCITE2\u0096UU\u0096E2-C1-12<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2024 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>EXCITE Network<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27027\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27027\" aria-expanded=\"false\" aria-controls=\"collapse-27027\">\n                                            MA-GMA: Protracted storage of monotonous andesite magma\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27027\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27027\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Jorge Romero recientemente ha adjudicado un proyecto EXCITE2 para realizar un el an\u00e1lisis petrol\u00f3gico de muestras del Complejo Volc\u00e1nico Tinguiririca a finales de 2024. La investigaci\u00f3n consistir\u00e1 en la investigaci\u00f3n con microsonda de electrones de fases minerales y vidrio de la masa molida, adem\u00e1s de geoqu\u00edmica de roca entera y dataci\u00f3n radiom\u00e9trica.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2024 - Septiembre 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27047\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Spatiotemporal dynamics of lithium in Andean salars: Insights for Sustainable Exploration and Exploitation\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27047\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27047\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]We propose to undertake a 3-year long project, devoted to achieving a detailed comprehension of the Li dynamics and impacts, from source to sink, in the Andean salars (including Preandean and high Andean salars) of the Antofagasta Region of Chile (Fig. 1). The methodological approach is multidisciplinary and includes geological, hydrological, mineralogical, geochemical, microbiological and social techniques. The specific study cases are given by the Salar de Atacama (SDA), recognized as the most important Li brine reservoir in Chile (Cabello, 2022), and 3 salt flats domains located eastwards; these latter domains are, from south to north:\r\nNorthern domain. Pujsa, Tara, and Quisquiro salt lakes.\r\nSouthern domain. Capur, Talar, and Tuyajto salt lakes. \r\nCentral domain. Aguas Calientes Sur and Laguna Lejia salt lakes.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2024 - Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Fundaci\u00f3n Palarq<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26155\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Primeros pasos humanos en Am\u00e9rica del Sur: caminando entre Gonfoterios\u0094 \u0096 Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26155\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26155\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Excavaciones arqueol\u00f3gicas y paleontol\u00f3gicas en el antiguo Lago Tagua Tagua[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> PINC230014<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2024 - Mayo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26182\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Prototipo de evaluaci\u00f3n multiescala para la toma de decisiones interdisciplinarias post-incendios forestales: recuperando los servicios ecosist\u00e9micos desde el suelo a paisajes multifuncionales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26182\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26182\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La presente propuesta busca generar un proceso de evaluaci\u00f3n r\u00e1pida de los efectos post-incendio a diferentes escalas, para la toma de decisiones informadas entre la academia y actores involucrados en la gesti\u00f3n preventiva, mitigaci\u00f3n y de recuperaci\u00f3n desde el suelo hasta paisajes funcionales. Considerando que (i) no se cuenta con una sistematizaci\u00f3n de los impactos de los incendios en los ecosistemas forestales a corto plazo, (ii) existe una falta de conocimiento sobre el papel que desempe\u00f1a el suelo en la respuesta de la vegetaci\u00f3n frente a incendios de diversas intensidades y severidades, y (iii) se ha experimentado un aumento significativo en la investigaci\u00f3n basada en sensores remotos debido a su alcance espacial y temporal, la presente propuesta consiste en la creaci\u00f3n de un prototipo de evaluaci\u00f3n multiescala para la toma de decisiones interdisciplinarias post-incendios forestales: recuperando los servicios ecosist\u00e9micos desde el suelo a paisajes multifuncionales. El producto obtenido como prototipo de soluci\u00f3n ser\u00e1 un proceso de levantamiento y validaci\u00f3n de informaci\u00f3n que permita integrar el conocimiento cient\u00edfico-t\u00e9cnico a la toma de decisiones post-incendios. El proceso de construcci\u00f3n del prototipo busca generar las bases para impactar de manera positiva la planificaci\u00f3n colaborativa, proactiva e informada de las acciones de evaluaci\u00f3n temprana de los efectos de los incendios en los ecosistemas, para la prevenci\u00f3n o mitigaci\u00f3n de los riesgos asociados a la ocurrencia de incendios y pr\u00e1cticas de recuperaci\u00f3n atendiendo dichas condiciones clim\u00e1ticas se hacen cada vez m\u00e1s evidentes.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI240013<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2024 - Junio 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26183\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Colaboraci\u00f3n internacional e interdisciplinaria para el estudio de riesgos de intrusi\u00f3n salina inducida por el cambio clim\u00e1tico en ecosistemas agr\u00edcolas costeros y sus efectos en servicios ecosist\u00e9micos de suelos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26183\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26183\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Los ecosistemas costeros son ambientes altamente susceptibles a los efectos del cambio\r\nclim\u00e1tico, para los cuales se proyecta a escala global un aumento en el nivel del mar de\r\nentre 0,5 y 1 m hacia el 2100. Una consecuencia importante del aumento del nivel del mar\r\nes la intrusi\u00f3n de agua salada, que se produce por el movimiento del agua de mar hacia los\r\ncontinentes. En Chile, el Ministerio del Medio Ambiente ha identificado las zonas m\u00e1s\r\nexpuestas (por debajo de los 10 m s.n.m) a fen\u00f3menos asociados al aumento del nivel del\r\nmar y cambios en la cota de inundaci\u00f3n en comunas de zonas costeras. Sin embargo, estos\r\nestudios no asocian la vulnerabilidad de dichos ecosistemas con fen\u00f3menos de intrusi\u00f3n\r\nsalina.\r\n\r\nEl aumento del nivel del mar y la entrada de agua salada a los continentes han demostrado\r\nafectar comunidades costeras, sistemas productivos como la agricultura, as\u00ed como servicios\r\necosist\u00e9micos relacionados con estos. Dentro de estos \u00faltimos, se encuentra la capacidad de\r\nlos suelos de proveer alimentos y de funcionar como un sumidero de carbono, y as\u00ed mitigar\r\nlos efectos del cambio clim\u00e1tico. Contrario de los avances de conocimiento en la materia a\r\nnivel internacional, en Chile se desconocen estudios sistem\u00e1ticos que eval\u00faen los riesgos de\r\nintrusi\u00f3n marina y su relaci\u00f3n con la agricultura y el desarrollo sostenible de zonas costeras\r\nen Chile. No obstante, estudios locales recientes destacan a las comunas de Pichilemu\r\n(regi\u00f3n de O'Higgins) y Maull\u00edn (regi\u00f3n de Los Lagos), como zonas vulnerables a\r\ninundaciones por el aumento del nivel del mar y que actualmente evidencian intrusi\u00f3n salina\r\ny afectaci\u00f3n de suelos agr\u00edcolas. En este contexto, para abordar de manera integral el\r\nimpacto de la intrusi\u00f3n marina en los territorios a nivel nacional, se requiere del desarrollo\r\nde la ciencia de resiliencia costera en Chile, as\u00ed como de nuevas t\u00e9cnicas para identificar con\r\n\u00e9xito la vulnerabilidad de los paisajes costeros y sistemas agr\u00edcolas a la intrusi\u00f3n de agua\r\nsalada, todo lo cual requiere la interacci\u00f3n de la academia y las comunidades locales, los\r\nagricultores y tomadores de decisiones.\r\n\r\nConsecuentemente, la presente propuesta tiene como objetivo crear una red internacional\r\nentre la Universidad de O\u0092Higgins, la Universidad de Chile y la Universidad de Maryland, con\r\nun enfoque interdisciplinar, es decir integrando las disciplinas de las ciencias agron\u00f3micas,\r\nciencias naturales y las ciencias sociales para abordar desaf\u00edos relacionados con la\r\nadaptaci\u00f3n de los sistemas agr\u00edcolas costeros y servicios ecosist\u00e9micos de suelos a los\r\nefectos de la intrusi\u00f3n marina. La red de colaboraci\u00f3n, a desplegar en Pichilemu y Maull\u00edn,\r\npermitir\u00e1 robustecer y abordar esta tem\u00e1tica en Chile, y as\u00ed contribuir al desarrollo de\r\nsoluciones en la materia con alcances a nivel nacional.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI240155<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2024 - Mayo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26191\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desentra\u00f1ando la importancia del microbioma vegetal en la adaptaci\u00f3n de la agricultura en zonas \u00e1ridas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26191\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26191\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"].[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> PINC230014<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2024 - Mayo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26491\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Prototipo de evaluaci\u00f3n multiescala para la toma de decisiones interdisciplinarias post-incendios forestales: recuperando los servicios ecosist\u00e9micos desde el suelo a paisajes multifuncionales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26491\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26491\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La presente propuesta busca generar un proceso de evaluaci\u00f3n r\u00e1pida de los efectos post-incendio a diferentes escalas, para la toma de decisiones informadas entre la academia y actores involucrados en la gesti\u00f3n preventiva, mitigaci\u00f3n y de recuperaci\u00f3n desde el suelo hasta paisajes funcionales. Considerando que (i) no se cuenta con una sistematizaci\u00f3n de los impactos de los incendios en los ecosistemas forestales a corto plazo, (ii) existe una falta de conocimiento sobre el papel que desempe\u00f1a el suelo en la respuesta de la vegetaci\u00f3n frente a incendios de diversas intensidades y severidades, y (iii) se ha experimentado un aumento significativo en la investigaci\u00f3n basada en sensores remotos debido a su alcance espacial y temporal, la presente propuesta consiste en la creaci\u00f3n de un prototipo de evaluaci\u00f3n multiescala para la toma de decisiones interdisciplinarias post-incendios forestales: recuperando los servicios ecosist\u00e9micos desde el suelo a paisajes multifuncionales. El producto obtenido como prototipo de soluci\u00f3n ser\u00e1 un proceso de levantamiento y validaci\u00f3n de informaci\u00f3n que permita integrar el conocimiento cient\u00edfico-t\u00e9cnico a la toma de decisiones post-incendios. El proceso de construcci\u00f3n del prototipo busca generar las bases para impactar de manera positiva la planificaci\u00f3n colaborativa, proactiva e informada de las acciones de evaluaci\u00f3n temprana de los efectos de los incendios en los ecosistemas, para la prevenci\u00f3n o mitigaci\u00f3n de los riesgos asociados a la ocurrencia de incendios y pr\u00e1cticas de recuperaci\u00f3n atendiendo dichas condiciones clim\u00e1ticas se hacen cada vez m\u00e1s evidentes.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26313\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Determinaci\u00f3n de micotoxinas estrog\u00e9nicas en mujeres con s\u00edndrome de ovario poliqu\u00edstico y su impacto a nivel hep\u00e1tico en un modelo celular\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26313\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26313\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las micotoxinas son metabolitos producidos por algunos hongos del tipo Aspergillus, Penicillum o Fusarium, contaminantes habituales de alimentos que necesitan secado como granos, frutos secos y condimentos. Las micotoxinas son extremadamente t\u00f3xicas y afectan tanto a animales como humanos; las de mayor significancia son la ocratoxina A, aflatoxina, fumonisina, tricotecenos y zearalenona. En t\u00e9rminos generales, las micotoxinas al ser ingeridas son absorbidas en el tracto gastrointestinal, metabolizadas en el h\u00edgado a trav\u00e9s de reacciones de Fase I (oxidaci\u00f3n) y Fase II (conjugaci\u00f3n), y finalmente excretadas por orina y heces. El principal \u00f3rgano afectado por la exposici\u00f3n a micotoxinas es el h\u00edgado, \u00f3rgano central del metabolismo, incrementando el tama\u00f1o hep\u00e1tico, el estr\u00e9s oxidativo y modificando los niveles de lisofosfatidilcolina, que puede aumentar la apoptosis a trav\u00e9s de la producci\u00f3n de especies reactivas de ox\u00edgeno.  Adem\u00e1s, se ha descrito que algunas de las micotoxinas pueden tener efectos endocrinos, principalmente de tipo estrog\u00e9nico. La zearalenona (ZEN) es una de las micotoxinas m\u00e1s importantes producidas por Fusarium spp. Los hongos del tipo Fusarium son uno de los m\u00e1s frecuentes encontrados en Chile, y se ve aumentada en condiciones de estr\u00e9s h\u00eddrico. La ZEN es termoestable y no se degrada por el procesamiento. La ZEN es una fusariotoxina estrog\u00e9nica, es decir se clasifica como un fitoestr\u00f3geno o como un micoestr\u00f3geno, ya que su estructura qu\u00edmica es an\u00e1loga a la de los estr\u00f3genos naturales. Esto permite su uni\u00f3n con los sitios receptores estrog\u00e9nicos, lo que conduce a una estrogenicidad amplificada. Como resultado, la intoxicaci\u00f3n por ZEN conduce con mayor frecuencia a disrupci\u00f3n endocrina y trastornos del sistema reproductivo. Los metabolitos hep\u00e1ticos pueden tener aun mayor afinidad con los receptores estrog\u00e9nicos; por ejemplo, el alfa-zearalenol (&#945;-ZEL) es 60 veces m\u00e1s estrog\u00e9nico que ZEN. Si bien en Chile se han realizado estudios de biomonitoreo de micotoxinas, no existe en la actualidad informaci\u00f3n sobre la exposici\u00f3n a ZEN y sus metabolitos especialmente en mujeres y sus posibles efectos como disruptores hormonales.\r\n\r\nEn este contexto, existe una condici\u00f3n endocrinometab\u00f3lica muy prevalente en la poblaci\u00f3n chilena denominada \u0093S\u00edndrome de ovario poliqu\u00edstico\u0094 (SOP), la cual se caracteriza por la presencia de un exceso de hormonas andr\u00f3genicas, irregularidad menstrual y morfolog\u00eda de ovarios poliqu\u00edsticos. Adem\u00e1s, las mujeres con SOP poseen un mayor riesgo de desarrollar alteraciones metab\u00f3licas como resistencia a la insulina, diabetes tipo 2, s\u00edndrome metab\u00f3lico y enfermedad cardiovascular, impactando su calidad de vida. El estudio de la fisiopatolog\u00eda del SOP es desafiante ya que es una condici\u00f3n muy heterog\u00e9nea, sin embargo, se ha descrito que el hiperandrogenismo, la disfunci\u00f3n ovulatoria, alteraciones en la pulsatilidad de la hormona liberadora de gonadotrofinas (GnRH) y la resistencia a la insulina, tienen un rol clave en el desarrollo de esta condici\u00f3n. Por otra parte, el exceso de andr\u00f3genos incrementa los niveles de insulina y reduce la producci\u00f3n de la globulina transportadora de hormonas sexuales (SHBG) en el h\u00edgado, lo que aumenta la circulaci\u00f3n de testosterona bioactiva libre. Adem\u00e1s, la hiperinsulinemia estimula la s\u00edntesis de andr\u00f3genos activando la v\u00eda de la esteroidog\u00e9nesis e incrementa estados de inflamaci\u00f3n y estr\u00e9s oxidativo, debido a la disfunci\u00f3n mitocondrial, promoviendo el desarrollo de un c\u00edrculo vicioso.  Sin embargo, la contribuci\u00f3n individual de estos factores puede variar entre las pacientes, dando cuenta de la heterogeneidad cl\u00ednica que se observa en la cl\u00ednica. Aunque en su etiolog\u00eda se han implicado factores gen\u00e9ticos y de estilo de vida, cada vez hay m\u00e1s pruebas de que la exposici\u00f3n a contaminantes ambientales, incluyendo los disruptores endocrinos, tambi\u00e9n pueden contribuir significativamente al desarrollo y la fisiopatolog\u00eda del SOP. En este contexto, el rol de las micotoxinas como disruptores endocrinos no ha sido estudiado extensamente en el contexto del SOP, y debido a posibles efectos acumulativos e interacciones sin\u00e9rgicas entre estos contaminantes, se requiere evaluar su potencial impacto en la fisiopatolog\u00eda del SOP. En particular, se ha considerado que las micotoxinas con actividad estrog\u00e9nica, como la zearalenona, podr\u00edan influir en el equilibrio hormonal de las mujeres y potencialmente contribuir al desarrollo o exacerbaci\u00f3n del SOP. De esta manera, el objetivo general de esta propuesta es evaluar los niveles circulantes de ZEN y sus metabolitos como posibles factores de riesgo dietarios, y determinar su posible asociaci\u00f3n con alteraciones endocrinometab\u00f3licas en mujeres chilenas con SOP. Este objetivo ser\u00e1 abordado mediante un estudio cl\u00ednico en mujeres chilenas y un estudio in vitro. \r\n\r\nLa investigaci\u00f3n propuesta aportar\u00e1 informaci\u00f3n valiosa y novedosa sobre c\u00f3mo factores dietarios contribuyen al desarrollo y severidad del SOP, abriendo nuevas v\u00edas para la comprensi\u00f3n y manejo de esta condici\u00f3n. Finalmente, esta propuesta se enmarca dentro del objetivo de vincular el ICA3 y el Instituto de Ciencias de la Salud, contribuyendo al objetivo estrat\u00e9gico de la Universidad de consolidar los Institutos de Investigaci\u00f3n mediante la colaboraci\u00f3n estrecha e interdisciplinaria. M\u00e1s a\u00fan, el estudio aportar\u00e1 con formaci\u00f3n de estudiantes de ambos institutos, la divulgaci\u00f3n y difusi\u00f3n de los resultados del proyecto.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26614\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Determinaci\u00f3n de micotoxinas estrog\u00e9nicas en mujeres con s\u00edndrome de ovario poliqu\u00edstico y su impacto a nivel hep\u00e1tico en un modelo celular\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26614\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26614\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las micotoxinas son metabolitos producidos por algunos hongos del tipo Aspergillus, Penicillum o Fusarium, contaminantes habituales de alimentos que necesitan secado como granos, frutos secos y condimentos. Las micotoxinas son extremadamente t\u00f3xicas y afectan tanto a animales como humanos; las de mayor significancia son la ocratoxina A, aflatoxina, fumonisina, tricotecenos y zearalenona. En t\u00e9rminos generales, las micotoxinas al ser ingeridas son absorbidas en el tracto gastrointestinal, metabolizadas en el h\u00edgado a trav\u00e9s de reacciones de Fase I (oxidaci\u00f3n) y Fase II (conjugaci\u00f3n), y finalmente excretadas por orina y heces. El principal \u00f3rgano afectado por la exposici\u00f3n a micotoxinas es el h\u00edgado, \u00f3rgano central del metabolismo, incrementando el tama\u00f1o hep\u00e1tico, el estr\u00e9s oxidativo y modificando los niveles de lisofosfatidilcolina, que puede aumentar la apoptosis a trav\u00e9s de la producci\u00f3n de especies reactivas de ox\u00edgeno.  Adem\u00e1s, se ha descrito que algunas de las micotoxinas pueden tener efectos endocrinos, principalmente de tipo estrog\u00e9nico. La zearalenona (ZEN) es una de las micotoxinas m\u00e1s importantes producidas por Fusarium spp. Los hongos del tipo Fusarium son uno de los m\u00e1s frecuentes encontrados en Chile, y se ve aumentada en condiciones de estr\u00e9s h\u00eddrico. La ZEN es termoestable y no se degrada por el procesamiento. La ZEN es una fusariotoxina estrog\u00e9nica, es decir se clasifica como un fitoestr\u00f3geno o como un micoestr\u00f3geno, ya que su estructura qu\u00edmica es an\u00e1loga a la de los estr\u00f3genos naturales. Esto permite su uni\u00f3n con los sitios receptores estrog\u00e9nicos, lo que conduce a una estrogenicidad amplificada. Como resultado, la intoxicaci\u00f3n por ZEN conduce con mayor frecuencia a disrupci\u00f3n endocrina y trastornos del sistema reproductivo. Los metabolitos hep\u00e1ticos pueden tener aun mayor afinidad con los receptores estrog\u00e9nicos; por ejemplo, el alfa-zearalenol (&#945;-ZEL) es 60 veces m\u00e1s estrog\u00e9nico que ZEN. Si bien en Chile se han realizado estudios de biomonitoreo de micotoxinas, no existe en la actualidad informaci\u00f3n sobre la exposici\u00f3n a ZEN y sus metabolitos especialmente en mujeres y sus posibles efectos como disruptores hormonales.\r\n\r\nEn este contexto, existe una condici\u00f3n endocrinometab\u00f3lica muy prevalente en la poblaci\u00f3n chilena denominada \u0093S\u00edndrome de ovario poliqu\u00edstico\u0094 (SOP), la cual se caracteriza por la presencia de un exceso de hormonas andr\u00f3genicas, irregularidad menstrual y morfolog\u00eda de ovarios poliqu\u00edsticos. Adem\u00e1s, las mujeres con SOP poseen un mayor riesgo de desarrollar alteraciones metab\u00f3licas como resistencia a la insulina, diabetes tipo 2, s\u00edndrome metab\u00f3lico y enfermedad cardiovascular, impactando su calidad de vida. El estudio de la fisiopatolog\u00eda del SOP es desafiante ya que es una condici\u00f3n muy heterog\u00e9nea, sin embargo, se ha descrito que el hiperandrogenismo, la disfunci\u00f3n ovulatoria, alteraciones en la pulsatilidad de la hormona liberadora de gonadotrofinas (GnRH) y la resistencia a la insulina, tienen un rol clave en el desarrollo de esta condici\u00f3n. Por otra parte, el exceso de andr\u00f3genos incrementa los niveles de insulina y reduce la producci\u00f3n de la globulina transportadora de hormonas sexuales (SHBG) en el h\u00edgado, lo que aumenta la circulaci\u00f3n de testosterona bioactiva libre. Adem\u00e1s, la hiperinsulinemia estimula la s\u00edntesis de andr\u00f3genos activando la v\u00eda de la esteroidog\u00e9nesis e incrementa estados de inflamaci\u00f3n y estr\u00e9s oxidativo, debido a la disfunci\u00f3n mitocondrial, promoviendo el desarrollo de un c\u00edrculo vicioso.  Sin embargo, la contribuci\u00f3n individual de estos factores puede variar entre las pacientes, dando cuenta de la heterogeneidad cl\u00ednica que se observa en la cl\u00ednica. Aunque en su etiolog\u00eda se han implicado factores gen\u00e9ticos y de estilo de vida, cada vez hay m\u00e1s pruebas de que la exposici\u00f3n a contaminantes ambientales, incluyendo los disruptores endocrinos, tambi\u00e9n pueden contribuir significativamente al desarrollo y la fisiopatolog\u00eda del SOP. En este contexto, el rol de las micotoxinas como disruptores endocrinos no ha sido estudiado extensamente en el contexto del SOP, y debido a posibles efectos acumulativos e interacciones sin\u00e9rgicas entre estos contaminantes, se requiere evaluar su potencial impacto en la fisiopatolog\u00eda del SOP. En particular, se ha considerado que las micotoxinas con actividad estrog\u00e9nica, como la zearalenona, podr\u00edan influir en el equilibrio hormonal de las mujeres y potencialmente contribuir al desarrollo o exacerbaci\u00f3n del SOP. De esta manera, el objetivo general de esta propuesta es evaluar los niveles circulantes de ZEN y sus metabolitos como posibles factores de riesgo dietarios, y determinar su posible asociaci\u00f3n con alteraciones endocrinometab\u00f3licas en mujeres chilenas con SOP. Este objetivo ser\u00e1 abordado mediante un estudio cl\u00ednico en mujeres chilenas y un estudio in vitro. \r\n\r\nLa investigaci\u00f3n propuesta aportar\u00e1 informaci\u00f3n valiosa y novedosa sobre c\u00f3mo factores dietarios contribuyen al desarrollo y severidad del SOP, abriendo nuevas v\u00edas para la comprensi\u00f3n y manejo de esta condici\u00f3n. Finalmente, esta propuesta se enmarca dentro del objetivo de vincular el ICA3 y el Instituto de Ciencias de la Salud, contribuyendo al objetivo estrat\u00e9gico de la Universidad de consolidar los Institutos de Investigaci\u00f3n mediante la colaboraci\u00f3n estrecha e interdisciplinaria. M\u00e1s a\u00fan, el estudio aportar\u00e1 con formaci\u00f3n de estudiantes de ambos institutos, la divulgaci\u00f3n y difusi\u00f3n de los resultados del proyecto.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>International Centre for Antimicrobial Resistance Solutions (ICARS)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25986\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Surveillance, alert, and response system (SVAR) for the use of antimicrobials in Chilean salmon farming\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25986\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25986\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The use of antimicrobials (AMU) in the salmon farming industry in Chile is concentrated in the sea fattening phase of the production cycle. In 2022, 91% of the AMU in fattening farms was for treatment of Piscirickettsia salmonis (Sernapesca, 2023), the main disease-causing pathogen affecting farmed salmon in Chile (Rozas and Enriquez, 2014).\r\n\r\nTo control P. salmonis, a series of preventive strategies have been adopted. Nevertheless, the incidence of P. salmonis remains high; resulting in high mortality rates (Jakob et al., 2014) and extensive AMU. The use of antimicrobials is exacerbated by current management practices in salmon farms as well as a lack of standardization in treatment guidelines and practices between veterinarians and companies (e.g. treatment of all or selected cages, dosage, etc.), but also because of limited consolidation, communication and use of available AMU data.\r\n\r\nThe aim of this project is to reduce antimicrobial consumption in salmon farming in Los Lagos and Aysen regions where P. salmonis is a challenge and improve science-based governance of AMU in the salmon farming sector through a surveillance, alert and response system (SVARS). The project will be implemented in two phases. Phase one will focus on increasing the knowledge of AMU drivers by developing a catalog of practices and factors that impact the use of antimicrobials and conduct a cost-effectiveness analysis to assess the more cost efficient alternative methods to AMU practices. The catalog will be compiled in a format that can be used to implement improvements on high AMU farms. Different AMU metrics will be reviewed and selected to differentiate farms with low, medium and high AMU. In addition, the legislative requirements to develop and sustain a surveillance, alert and response system (SVARS) to reduce AMU in Chilean salmon farming will be reviewed. Finally, the infrastructural and operational requirements for the platform will be assessed and the design of the platform will be completed, integrating geospatial and health information.\r\n\r\nIn phase two, the SVARS will categorize the farms based on their AMU levels. The high use farms will be recruited to a Randomized Controlled Trial where intervention farms will implement practices and methods from the catalog created in phase one to reduce AMU. The outcomes and the effectiveness of the SVARS will be quantitatively and qualitatively assessed. Finally, results and outcomes of establishing and implementing the SVARS will be shared with relevant stakeholders in Chile, to low-and middle-income countries in the region and beyond, e.g. through workshops and education training programs in order to disseminate the results.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2024 - Agosto 2028<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26397\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Sistema integrado de manejo del nematodo de la frutilla \u0093SIMCANEM\u0094 un modelo sustentable y de innovaci\u00f3n para la agricultura familiar campesina en la regi\u00f3n de O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26397\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26397\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]A. fragariae ataca las partes a\u00e9reas de las plantas y el nematodo puede adoptar\r\ncomportamientos de endo y ectopar\u00e1sito. El nematodo puede pasar por m\u00faltiples ciclos de vida\r\nen una temporada de crecimiento de la frutilla cuando se presentan condiciones favorables. Los\r\nnematodos penetran a trav\u00e9s de los estomas y ocasionan da\u00f1os en coronas, estolones, follaje,\r\nbrotes nuevos e incluso en las frutas. El riesgo que representa Af en la agricultura es muy alto\r\nya que se han reportado m\u00e1s de 600 especies de plantas de 47 familias que sirven de\r\nhospedadores, algunas de ellas con relevancia para la agricultura familiar campesina regional\r\ncomo: cebollas, cebollines, ajos (entre otras), y ornamentales (peon\u00edas, begonias, helechos,\r\netc).\r\nDe acuerdo a datos recopilados por INDAP a trav\u00e9s de sus programas de PRODESAL y SAT\r\ncerca del 90% de la actividad productiva de la frutilla en la regi\u00f3n de O\u0092Higgins est\u00e1 concentrada\r\nen la agricultura familiar campesina (AFC) (101 productores) y 24 % corresponde predios\r\nmanejados por mujeres. La mayor\u00eda de \u00e9stos concentrados en las comunas del Secano Costero\r\nde la regi\u00f3n. Sin embargo, a medida que el problema del Af avanza, se han ido detectando otros\r\npeque\u00f1os productores en otras comunas de la regi\u00f3n que no son beneficiaros de instituciones\r\ncomo el INDAP pero que tambi\u00e9n presentan problemas. En este escenario, las medidas que se\r\npuedan tomar para el control de Af toman mayor relevancia, porque su presencia tiene\r\nconsecuencias no s\u00f3lo fitosanitarias sino econ\u00f3micos y sociales.\r\nAphelenchoides fragariae es dif\u00edcil de manejar debido a que poseen un ciclo de vida robusto que\r\nles permite permanecer vivos en la planta, material vegetal seco y suelo. Los nematodos adultos\r\npueden sobrevivir a la desecaci\u00f3n y permanecer inactivos durante varios meses. Adem\u00e1s, los\r\npesticidas sint\u00e9ticos que se usan para su control tienen una eficiencia limitada. Es por ello, que\r\npara tener un control efectivo de Af, es imprescindible cambiar los paradigmas de control\r\ntradicionales por un sistema de manejo integrado que sea i) de f\u00e1cil adopci\u00f3n, ii) que permita\r\ngenerar ingresos a pesar de la plaga y iii) que posea componentes que protejan al medio\r\nambiente de la dependencia de pesticidas sint\u00e9ticos y iv) que proteja el tejido social y econ\u00f3mico\r\nde la actividad productiva. Por lo tanto, y tomando en cuenta la agresividad de esta plaga, es\r\nimportante tomar medidas urgentes para reducir el impacto de Af a largo plazo.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2024 - Agosto 2028<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26897\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Sistema integrado de manejo del nematodo de la frutilla \u0093SIMCANEM\u0094 un modelo sustentable y de innovaci\u00f3n para la agricultura familiar campesina en la regi\u00f3n de O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26897\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26897\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]A. fragariae ataca las partes a\u00e9reas de las plantas y el nematodo puede adoptar\r\ncomportamientos de endo y ectopar\u00e1sito. El nematodo puede pasar por m\u00faltiples ciclos de vida\r\nen una temporada de crecimiento de la frutilla cuando se presentan condiciones favorables. Los\r\nnematodos penetran a trav\u00e9s de los estomas y ocasionan da\u00f1os en coronas, estolones, follaje,\r\nbrotes nuevos e incluso en las frutas. El riesgo que representa Af en la agricultura es muy alto\r\nya que se han reportado m\u00e1s de 600 especies de plantas de 47 familias que sirven de\r\nhospedadores, algunas de ellas con relevancia para la agricultura familiar campesina regional\r\ncomo: cebollas, cebollines, ajos (entre otras), y ornamentales (peon\u00edas, begonias, helechos,\r\netc).\r\nDe acuerdo a datos recopilados por INDAP a trav\u00e9s de sus programas de PRODESAL y SAT\r\ncerca del 90% de la actividad productiva de la frutilla en la regi\u00f3n de O\u0092Higgins est\u00e1 concentrada\r\nen la agricultura familiar campesina (AFC) (101 productores) y 24 % corresponde predios\r\nmanejados por mujeres. La mayor\u00eda de \u00e9stos concentrados en las comunas del Secano Costero\r\nde la regi\u00f3n. Sin embargo, a medida que el problema del Af avanza, se han ido detectando otros\r\npeque\u00f1os productores en otras comunas de la regi\u00f3n que no son beneficiaros de instituciones\r\ncomo el INDAP pero que tambi\u00e9n presentan problemas. En este escenario, las medidas que se\r\npuedan tomar para el control de Af toman mayor relevancia, porque su presencia tiene\r\nconsecuencias no s\u00f3lo fitosanitarias sino econ\u00f3micos y sociales.\r\nAphelenchoides fragariae es dif\u00edcil de manejar debido a que poseen un ciclo de vida robusto que\r\nles permite permanecer vivos en la planta, material vegetal seco y suelo. Los nematodos adultos\r\npueden sobrevivir a la desecaci\u00f3n y permanecer inactivos durante varios meses. Adem\u00e1s, los\r\npesticidas sint\u00e9ticos que se usan para su control tienen una eficiencia limitada. Es por ello, que\r\npara tener un control efectivo de Af, es imprescindible cambiar los paradigmas de control\r\ntradicionales por un sistema de manejo integrado que sea i) de f\u00e1cil adopci\u00f3n, ii) que permita\r\ngenerar ingresos a pesar de la plaga y iii) que posea componentes que protejan al medio\r\nambiente de la dependencia de pesticidas sint\u00e9ticos y iv) que proteja el tejido social y econ\u00f3mico\r\nde la actividad productiva. Por lo tanto, y tomando en cuenta la agresividad de esta plaga, es\r\nimportante tomar medidas urgentes para reducir el impacto de Af a largo plazo.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1241971<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2024 - Agosto 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26463\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            From hyper drought to heavy rainfall: assessing changes in the frequency of hydroclimatic extremes events and their impacts on forest ecosystems to support climate risk planning in Chile.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26463\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26463\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Climate change is driving new interactions between human communities and the environment. The impacts of climate extremes and the progressive patterns of changes in precipitation and temperature are creating new risk dynamics and a high diversity of ecological responses, new interactions between species, and adaptation pathways from society. Climate risk assessment is a crucial tool in current climate change science for developing adaptation and resilience plans and actions. In Chile, the recently enacted climate change law mandates the creation of climate action plans at the communal, basin, and regional levels, requiring climate risk studies as a first step to design adaptation processes, reduce climate risks, and foster resilience at different scales.\r\nOver the past decade, extremely unusual drought and large mass movement triggered by intense precipitation has produced important cost and life losses in the Mediterranean and Temperate territories, respectively. The mega-drought in the Mediterranean region has led to extensive tree mortality and forest decay, which is vary geographically diverse and heterogeneous, and remain unassessed in terms of impacts (exposition), vulnerability, and resilience. Years of extreme drought, known as \"hyper-droughts,\" have the potential to profoundly impact biomass dynamics and greenhouse gas emissions. The climatic conditions in the years preceding hyper-droughts play a crucial role in the response and resilience of tree species and forest communities, particularly concerning mortality, decomposition, growth, and regeneration processes. The effects of extreme drought can also trigger environmental changes that increase the risk of other hazards such as forest fires or heatwaves, resulting in areas where the climate risk increases, and consequently the priority for adaptation and resilience planning.\r\nIn recent decades, massive mass movements, including landslides and debris flows, have become a significant climate hazard in North Patagonia, particularly associated with intense precipitation events. Understanding the frequency of mass movements and their relationship to intense precipitation and other climatic factors is essential for climate change action plans and climate risk assessment.\r\nIn this context, our proposal aims to develop the first studies using multi-proxy techniques to enhance environmental information for climate risk assessment and integrate it into climate action plans in the Mediterranean and Temperate climate of Chile. First, we will identify and reconstruct the hyper-droughts in the Mediterranean area and pluvial extremes in North Patagonia using historical documents, instrumental and tree-ring records. We will analyze the hyper-drought records to assess the influence of prior climatic variability on forest response and resilience, as well as the drought vulnerability of different Mediterranean forests at high and mid elevations. This assessment will include estimations of structural and functional diversity. Simultaneously, we will reconstruct mass movements using remote sensing, historical documents, and dendrogeomorphology techniques. By examining the frequency of mass movements, we will investigate the role of pluvial extremes and climate variability in their occurrence, especially important for climate risk assessment in the North Patagonian fjord systems, where the extension of the \"Carretera Austral\" is planned in the near future. This project will generate one of the longest and most precise records of hyper-droughts in the Mediterranean climate and mass movements associated with pluvial events in the North Patagonian Andean fjords of Chile. Additionally, it will provide initial estimations of forest vulnerability to hyper-droughts in Chile. These records are essential environmental information for climate risk assessment and climate action plans mandated by the new climate change legislation in Chile.\r\nTo ensure effective dissemination, we will communicate our results to the local community through infographics and seminars. We will engage with policy makers, such as Climate Change regional committees, local governments, and environmental risk public services, through meetings, workshops, and policy papers. Furthermore, we will promote the sharing of our results within the scientific community through scientific articles, research visits, international exchanges, and conference participation.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> Proyecto N\u00b085240326<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26501\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortaleciendo la ciencia social territorial: desastres y gobernanza en la regi\u00f3n de O&#8217;Higgins.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26501\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26501\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En esta postulaci\u00f3n se propone la instalaci\u00f3n del Dr. Ricardo Fuentealba en el Instituto de Ciencias Sociales de la Universidad de O'Higgins. La propuesta, titulada \u0093Fortaleciendo la ciencia social territorial: desastres y gobernanza en la regi\u00f3n de O'Higgins\u0094, tiene como objetivo desarrollar una agenda de investigaci\u00f3n basada en el desarrollo de los territorios de la regi\u00f3n. En particular, busca analizar de los procesos asociados a la gobernanza territorial y la producci\u00f3n de riesgo de desastre, entender las experiencias y pr\u00e1cticas de las comunidades con inundaciones recientes, y en base a ello, contribuir a la mejora de esta gobernanza. Con ello, se busca fortalecer el capital humano interdisciplinario de las ciencias sociales en la universidad, con un foco en los desastres y el desarrollo territorial. El acad\u00e9mico incorpora as\u00ed al Instituto una l\u00ednea de investigaci\u00f3n que tiene gran relevancia en el contexto del cambio clim\u00e1tico y el bienestar de la regi\u00f3n y el pa\u00eds.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> Proyecto N\u00b085240326<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26513\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortaleciendo la ciencia social territorial: desastres y gobernanza en la regi\u00f3n de O&#8217;Higgins.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26513\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26513\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En esta postulaci\u00f3n se propone la instalaci\u00f3n del Dr. Ricardo Fuentealba en el Instituto de Ciencias Sociales de la Universidad de O'Higgins. La propuesta, titulada \u0093Fortaleciendo la ciencia social territorial: desastres y gobernanza en la regi\u00f3n de O'Higgins\u0094, tiene como objetivo desarrollar una agenda de investigaci\u00f3n basada en el desarrollo de los territorios de la regi\u00f3n. En particular, busca analizar de los procesos asociados a la gobernanza territorial y la producci\u00f3n de riesgo de desastre, entender las experiencias y pr\u00e1cticas de las comunidades con inundaciones recientes, y en base a ello, contribuir a la mejora de esta gobernanza. Con ello, se busca fortalecer el capital humano interdisciplinario de las ciencias sociales en la universidad, con un foco en los desastres y el desarrollo territorial. El acad\u00e9mico incorpora as\u00ed al Instituto una l\u00ednea de investigaci\u00f3n que tiene gran relevancia en el contexto del cambio clim\u00e1tico y el bienestar de la regi\u00f3n y el pa\u00eds.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> LINCG24018<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>CSIC Espa\u00f1a<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26184\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Recuperaci\u00f3n de suelos urbanos, periurbanos y mineros mediante enmiendas org\u00e1nicas y biochar: el secuestro de carbono y la retenci\u00f3n de agua como herramientas de mitigaci\u00f3n del cambio clim\u00e1tico (SEQCHAR)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26184\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26184\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto de colaboraci\u00f3n internacional entre Espa\u00f1a, Chile, Argentina y Ecuador. El proyecto aborda la recuperaci\u00f3n de suelos degradados a trav\u00e9s del uso de enmiendas org\u00e1nicas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> LINCG24018<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>CSIC Espa\u00f1a<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26460\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Recuperaci\u00f3n de suelos urbanos, periurbanos y mineros mediante enmiendas org\u00e1nicas y biochar: el secuestro de carbono y la retenci\u00f3n de agua como herramientas de mitigaci\u00f3n del cambio clim\u00e1tico (SEQCHAR)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26460\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26460\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto de colaboraci\u00f3n internacional entre Espa\u00f1a, Chile, Argentina y Ecuador. El proyecto aborda la recuperaci\u00f3n de suelos degradados a trav\u00e9s del uso de enmiendas org\u00e1nicas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> LINCG24018<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>CSIC Espa\u00f1a<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26778\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Recuperaci\u00f3n de suelos urbanos, periurbanos y mineros mediante enmiendas org\u00e1nicas y biochar: el secuestro de carbono y la retenci\u00f3n de agua como herramientas de mitigaci\u00f3n del cambio clim\u00e1tico (SEQCHAR)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26778\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26778\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto de colaboraci\u00f3n internacional entre Espa\u00f1a, Chile, Argentina y Ecuador. El proyecto aborda la recuperaci\u00f3n de suelos degradados a trav\u00e9s del uso de enmiendas org\u00e1nicas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2024 - Abril 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Centro de Investigaci\u00f3n Avanzada en Educaci\u00f3n - CIAE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26213\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Experiencias de dise\u00f1o e implementaci\u00f3n de una Estrategia de Transici\u00f3n Educativa (ETE) en el ciclo inicial de establecimientos educacionales acompa\u00f1ados por un SLEP.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26213\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26213\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto plantea investigar las caracter\u00edsticas de este acompa\u00f1amiento desde los niveles directivos hasta su implementaci\u00f3n en las aulas. El prop\u00f3sito es indagar c\u00f3mo se lleva a cabo el trabajo colaborativo en diferentes niveles: directivos, docentes; al mismo tiempo, se explora c\u00f3mo esta colaboraci\u00f3n facilita el dise\u00f1o y la implementaci\u00f3n de estrategias de transici\u00f3n que apoyen el paso entre la EP y la EB, tanto para los ni\u00f1os y ni\u00f1as como para los equipos pedag\u00f3gicos. Para ello se utilizar\u00e1 un dise\u00f1o de estudios de casos m\u00faltiples (diferentes SLEP), con un enfoque mixto  de car\u00e1cter primordialmente cuantitativo  a trav\u00e9s de la aplicaci\u00f3n de cuestionarios de preguntas cerradas y abiertas. Estos cuestionarios son los planteados por Dockett & Perry (2006), uno para los directivos de la instituci\u00f3n educativa, \"Survey of Current Transition Programs\", y el otro para educadoras de p\u00e1rvulos y profesores de educaci\u00f3n b\u00e1sica, \"Overview of Current Transition Practices\". Estos cuestionarios miden elementos que son centrales al dise\u00f1o e implementaci\u00f3n de una estrategia de transici\u00f3n educativa (tal como se especifican en el Decreto 373), como por ejemplo contar con un programa de transici\u00f3n, involucrar la participaci\u00f3n de ni\u00f1os, ni\u00f1as y sus familias, recoger las perspectivas del equipo educativo, entre otras. Los cuestionarios contienen preguntas con alternativas, escalas de valoraci\u00f3n y preguntas abiertas. Estas \u00faltimas nos permiten profundizar en las perspectivas de los participantes y realizar un an\u00e1lisis cualitativo de sus respuestas. La aplicaci\u00f3n de estos instrumentos se realizar\u00e1 v\u00eda plataforma online y ser\u00e1n dirigidos tanto a directivos\/as como a UTP, Coordinadores, Educadoras y Profesores de los establecimientos educativos participantes. Se solicitar\u00e1 un consentimiento informado previo a la aplicaci\u00f3n de los cuestionarios el cual estar\u00e1 visado por el comit\u00e9 \u00e9tico de la Universidad de O\u0092Higgins.\r\n\r\nPregunta de investigaci\u00f3n: \u00bfDe qu\u00e9 manera se han implementado las orientaciones del Decreto Exento 373 para el dise\u00f1o e implementaci\u00f3n de una Estrategia de Transici\u00f3n Educativa (ETE) en establecimientos educativos que cuentan con el Apoyo T\u00e9cnico Pedag\u00f3gico de un SLEP?\r\n\r\nObjetivos:\r\n-\tEvaluar la percepci\u00f3n de los directivos y docentes sobre el impacto de la estrategia de transici\u00f3n educativa en sus establecimientos educativos.\r\n-\tAnalizar la comprensi\u00f3n y aplicaci\u00f3n de las orientaciones del Decreto Exento 373 por parte de los directivos y docentes.\r\n-\tIdentificar los desaf\u00edos y obst\u00e1culos enfrentados por los establecimientos educativos en la implementaci\u00f3n de la Estrategia de Transici\u00f3n Educativa seg\u00fan las orientaciones del Decreto Exento 373.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2024 - Abril 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Centro de Investigaci\u00f3n Avanzada en Educaci\u00f3n - CIAE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26369\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Experiencias de dise\u00f1o e implementaci\u00f3n de una Estrategia de Transici\u00f3n Educativa (ETE) en el ciclo inicial de establecimientos educacionales acompa\u00f1ados por un SLEP.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26369\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26369\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto plantea investigar las caracter\u00edsticas de este acompa\u00f1amiento desde los niveles directivos hasta su implementaci\u00f3n en las aulas. El prop\u00f3sito es indagar c\u00f3mo se lleva a cabo el trabajo colaborativo en diferentes niveles: directivos, docentes; al mismo tiempo, se explora c\u00f3mo esta colaboraci\u00f3n facilita el dise\u00f1o y la implementaci\u00f3n de estrategias de transici\u00f3n que apoyen el paso entre la EP y la EB, tanto para los ni\u00f1os y ni\u00f1as como para los equipos pedag\u00f3gicos. Para ello se utilizar\u00e1 un dise\u00f1o de estudios de casos m\u00faltiples (diferentes SLEP), con un enfoque mixto  de car\u00e1cter primordialmente cuantitativo  a trav\u00e9s de la aplicaci\u00f3n de cuestionarios de preguntas cerradas y abiertas. Estos cuestionarios son los planteados por Dockett & Perry (2006), uno para los directivos de la instituci\u00f3n educativa, \"Survey of Current Transition Programs\", y el otro para educadoras de p\u00e1rvulos y profesores de educaci\u00f3n b\u00e1sica, \"Overview of Current Transition Practices\". Estos cuestionarios miden elementos que son centrales al dise\u00f1o e implementaci\u00f3n de una estrategia de transici\u00f3n educativa (tal como se especifican en el Decreto 373), como por ejemplo contar con un programa de transici\u00f3n, involucrar la participaci\u00f3n de ni\u00f1os, ni\u00f1as y sus familias, recoger las perspectivas del equipo educativo, entre otras. Los cuestionarios contienen preguntas con alternativas, escalas de valoraci\u00f3n y preguntas abiertas. Estas \u00faltimas nos permiten profundizar en las perspectivas de los participantes y realizar un an\u00e1lisis cualitativo de sus respuestas. La aplicaci\u00f3n de estos instrumentos se realizar\u00e1 v\u00eda plataforma online y ser\u00e1n dirigidos tanto a directivos\/as como a UTP, Coordinadores, Educadoras y Profesores de los establecimientos educativos participantes. Se solicitar\u00e1 un consentimiento informado previo a la aplicaci\u00f3n de los cuestionarios el cual estar\u00e1 visado por el comit\u00e9 \u00e9tico de la Universidad de O\u0092Higgins.\r\n\r\nPregunta de investigaci\u00f3n: \u00bfDe qu\u00e9 manera se han implementado las orientaciones del Decreto Exento 373 para el dise\u00f1o e implementaci\u00f3n de una Estrategia de Transici\u00f3n Educativa (ETE) en establecimientos educativos que cuentan con el Apoyo T\u00e9cnico Pedag\u00f3gico de un SLEP?\r\n\r\nObjetivos:\r\n-\tEvaluar la percepci\u00f3n de los directivos y docentes sobre el impacto de la estrategia de transici\u00f3n educativa en sus establecimientos educativos.\r\n-\tAnalizar la comprensi\u00f3n y aplicaci\u00f3n de las orientaciones del Decreto Exento 373 por parte de los directivos y docentes.\r\n-\tIdentificar los desaf\u00edos y obst\u00e1culos enfrentados por los establecimientos educativos en la implementaci\u00f3n de la Estrategia de Transici\u00f3n Educativa seg\u00fan las orientaciones del Decreto Exento 373.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2024 - Julio 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26586\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            EstApp: Una aplicaci\u00f3n inteligente para la ense\u00f1anza y aprendizaje de la estad\u00edstica en educaci\u00f3n superior\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26586\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26586\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo General\r\nDesarrollar una aplicaci\u00f3n m\u00f3vil y web, centrada en los usuarios, para la ense\u00f1anza y aprendizaje inteligente de la estad\u00edstica en educaci\u00f3n superior.\r\nObjetivos Espec\u00edficos\r\n1.     Analizar los requerimientos funcionales y no funcionales que estructuran y esquematizan las versiones web de una aplicaci\u00f3n para la ense\u00f1anza y aprendizaje de la estad\u00edstica en educaci\u00f3n superior.\r\n2.     Dise\u00f1ar la arquitectura, base de datos y herramientas tecnol\u00f3gicas que dar\u00e1n sustento a una aplicaci\u00f3n para la ense\u00f1anza y aprendizaje de la estad\u00edstica en educaci\u00f3n superior.\r\n3.     Construir una aplicaci\u00f3n m\u00f3vil y web para la ense\u00f1anza y aprendizaje de la estad\u00edstica en educaci\u00f3n superior.\r\n4.     Validar la aplicaci\u00f3n resultante en t\u00e9rminos de sus funcionalidades y restricciones identificadas por los usuarios (profesores y estudiantes) mediante pruebas de software.\r\n5.     Evaluar la usabilidad y experiencia del usuario de la aplicaci\u00f3n con usuarios reales, en contextos de ense\u00f1anza y aprendizaje de la estad\u00edstica en educaci\u00f3n superior.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2024 - Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26762\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Iconograf\u00edas de la intolerancia: Imaginarios de odio en g\u00e9nero y migraci\u00f3n en Chile Contempor\u00e1neo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26762\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26762\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto tiene por objetivo general: Analizar la transmisi\u00f3n de im\u00e1genes de odio en la esfera p\u00fablica en el contexto nacional contempor\u00e1neo, en temas asociados a g\u00e9nero y migraci\u00f3n.\r\n\r\nComo objetivos espec\u00edficos, se propone:\r\nOE1. Identificar tipolog\u00edas de im\u00e1genes de odio que circulan en la opini\u00f3n p\u00fablica (medios de prensa y redes sociales) en temas asociados a g\u00e9nero y migraci\u00f3n. En este objetivo espec\u00edfico se indagar\u00e1 en diversas dimensiones: (1) caracter\u00edsticas visuales; (2) composici\u00f3n: (3) elementos performativos -gesto, expresiones, posturas-.\r\nOE2. Analizar c\u00f3mo se transmiten los imaginarios de odio, en temas asociado a g\u00e9nero y migraci\u00f3n en medios de circulaci\u00f3n masiva -medios de prensa y RRSS. Este objetivo busca estudiar los mensajes impl\u00edcitos y expl\u00edcitos que se transmiten por medio de las im\u00e1genes y c\u00f3mo se relacionan entre ellos, ahondando en la efectividad\r\ncomunicativa que posee.\r\nOE3. Propone un modelo metodol\u00f3gico para el estudio de imaginarios de odio en la esfera p\u00fablica. El objetivo busca sistematizar algunas estrategias metodol\u00f3gicas apropiadas para el estudio de las im\u00e1genes, proponiendo un modelo de an\u00e1lisis, a la vez de reflexionar sobre los desaf\u00edos y limitaciones \u00e9ticas de un an\u00e1lisis de esta \u00edndole en el contexto de las ciencias sociales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> Fondap 15130009<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2024 - Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Centro de Estudios de Conflicto y Cohesi\u00f3n Social<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26915\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Mujeres en la academia: Or\u00edgenes, avances y desaf\u00edos en la implementaci\u00f3n de pol\u00edticas de equidad de g\u00e9nero\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26915\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26915\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Uno de los principales aportes de las ciencias sociales es identificar problem\u00e1ticas relacionadas con desigualdades estructurales. Parte de esta tarea ha consistido en investigar y contribuir a visibilizar y erradicar la desigualdad de g\u00e9nero (Mora et al., 2018). En Chile, desde los 80s han surgido unidades de estudios, principalmente en la Regi\u00f3n Metropolitana, que han contribuido a difundir y consolidar las problem\u00e1ticas de g\u00e9nero, dentro y fuera de la academia, como una prioridad en la agenda nacional.1 Por otro lado, los movimientos sociales de los \u00faltimos a\u00f1os, particularmente el \u0093Mayo Feminista\u0094 del a\u00f1o 2018, expusieron situaciones de abusos de poder y laboral en la academia, brechas de g\u00e9nero y desaf\u00edos relacionados con los derechos de mujeres y disidencias (de Fina & Vidal, 2019). Impulsadas por estas manifestaciones, algunas instituciones de educaci\u00f3n superior han ejecutado acciones como la incorporaci\u00f3n de protocolos y reglamentos universitarios con perspectiva de g\u00e9nero. Desde el a\u00f1o 2019, el Ministerio de Ciencias, Tecnolog\u00eda, Conocimiento e Innovaci\u00f3n (MinCiencias) ha trabajado en incorporar pol\u00edticas de g\u00e9nero en el ecosistema de Ciencia, Tecnolog\u00eda, Conocimiento e Innovaci\u00f3n para el desarrollo (CTCI), creando los denominados Consejos de Igualdad y publicando una \u0093Radiograf\u00eda de G\u00e9nero\u0094 cada a\u00f1o (CTCI, 2020; 2022; 2023). Tambi\u00e9n, frente a la presi\u00f3n de los movimientos feministas en 2021 entr\u00f3 en vigencia la Ley N\u00ba 21.369 que regula el acoso sexual, la violencia y la discriminaci\u00f3n de g\u00e9nero en Educaci\u00f3n Superior. Asimismo, desde ese mismo a\u00f1o, la Agencia Nacional de Investigaci\u00f3n y Desarrollo (ANID) introdujo el fondo concursable \u0093Innovaci\u00f3n en Educaci\u00f3n Superior (InES) G\u00e9nero\u0094 con el objetivo de desarrollar capacidades para la implementaci\u00f3n de un plan de desarrollo en universidades que permita disminuir las brechas de g\u00e9nero en los \u00e1mbitos de investigaci\u00f3n, desarrollo, innovaci\u00f3n y emprendimiento (I+D+i+e) de base cient\u00edfica tecnol\u00f3gica.\r\n\r\nEn este contexto, nuestra propuesta tiene como objetivo general examinar la implementaci\u00f3n de las pol\u00edticas gubernamentales para la igualdad de g\u00e9nero en educaci\u00f3n superior y en el ecosistema CTCI en universidades chilenas y los cambios ocurridos en inserci\u00f3n, uso de tiempo y criterios de productividad acad\u00e9mica en disciplinas de las ciencias sociales, entre los a\u00f1os 2014 y 2024.\r\n\r\nObjetivos espec\u00edficos (OE):\r\nOE1. Realizar una revisi\u00f3n sistem\u00e1tica de las distintas pol\u00edticas gubernamentales para la igualdad de g\u00e9nero en educaci\u00f3n superior y en el ecosistema CTCI, analizando la coherencia con aquellas institucionalizadas en la pr\u00e1ctica por universidades chilenas entre 2014 y 2024.\r\nOE2. Analizar el impacto de los movimientos sociales y en particular, el movimiento feminista, en la institucionalizaci\u00f3n de pol\u00edticas en las universidades chilenas entre 2014 y 2024.\r\nOE3. Caracterizar los cambios en condiciones de trabajo y distribuci\u00f3n del tiempo en actividades que realizan las plantas acad\u00e9micas de las ciencias sociales de universidades chilenas entre 2014 y 2024, con un enfoque interseccional.2\r\nOE4. Analizar bajo una perspectiva feminista los criterios de productividad acad\u00e9mica tradicionales en las ciencias sociales, cuantificarlos con un enfoque interseccional y proponer un nuevo indicador de productividad acad\u00e9mica con perspectiva de g\u00e9nero.\r\nOE5. Identificar y sistematizar buenas pr\u00e1cticas y desaf\u00edos en la implementaci\u00f3n de pol\u00edticas institucionales para la igualdad de g\u00e9nero y su relaci\u00f3n con los cambios en inserci\u00f3n, uso de tiempo y productividad acad\u00e9mica en escuelas de ciencias sociales de universidades chilenas entre 2014 y 2024.\r\n\r\nEl proyecto contribuir\u00e1 a sistematizar y difundir los avances y desaf\u00edos en t\u00e9rminos de equidad de g\u00e9nero en la producci\u00f3n de conocimiento en el campo de ciencias sociales en Chile, as\u00ed como proponer soluciones para avanzar hacia el cierre de las brechas actualmente existentes, mejorar las condiciones laborales y los criterios de reconocimiento y jerarquizaci\u00f3n. En efecto, escasa atenci\u00f3n se ha dado sobre la situaci\u00f3n de las plantas acad\u00e9micas de las ciencias sociales, ya que, investigaciones previas han priorizado el campo de las ciencias, tecnolog\u00eda, ingenier\u00eda, y matem\u00e1ticas (STEM). No obstante, desde el MinCiencias se ha reconocido la necesidad de extender las mediciones a otras \u00e1reas del conocimiento, y sumar perspectivas como la interseccional (CTCI, 2022).[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2024 - Julio 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26978\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            EstApp: Una aplicaci\u00f3n inteligente para la ense\u00f1anza y aprendizaje de la estad\u00edstica en educaci\u00f3n superior\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26978\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26978\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo General\r\nDesarrollar una aplicaci\u00f3n m\u00f3vil y web, centrada en los usuarios, para la ense\u00f1anza y aprendizaje inteligente de la estad\u00edstica en educaci\u00f3n superior.\r\nObjetivos Espec\u00edficos\r\n1.     Analizar los requerimientos funcionales y no funcionales que estructuran y esquematizan las versiones web de una aplicaci\u00f3n para la ense\u00f1anza y aprendizaje de la estad\u00edstica en educaci\u00f3n superior.\r\n2.     Dise\u00f1ar la arquitectura, base de datos y herramientas tecnol\u00f3gicas que dar\u00e1n sustento a una aplicaci\u00f3n para la ense\u00f1anza y aprendizaje de la estad\u00edstica en educaci\u00f3n superior.\r\n3.     Construir una aplicaci\u00f3n m\u00f3vil y web para la ense\u00f1anza y aprendizaje de la estad\u00edstica en educaci\u00f3n superior.\r\n4.     Validar la aplicaci\u00f3n resultante en t\u00e9rminos de sus funcionalidades y restricciones identificadas por los usuarios (profesores y estudiantes) mediante pruebas de software.\r\n5.     Evaluar la usabilidad y experiencia del usuario de la aplicaci\u00f3n con usuarios reales, en contextos de ense\u00f1anza y aprendizaje de la estad\u00edstica en educaci\u00f3n superior.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ATE240017<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27085\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Proyecto Anillo  \u0093Sociotecnolog\u00edas del Litio\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27085\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27085\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La crisis socioecol\u00f3gica global ha desembocado en un proceso de transici\u00f3n hacia la sustentabilidad, en un primer  momento esta transici\u00f3n busca reemplazar el uso extensivo de combustibles f\u00f3siles por la utilizaci\u00f3n de energ\u00edas  provenientes de fuentes verdes. En este contexto, el Litio y otros minerales cada vez son m\u00e1s demandados  internacionalmente, debido a su funcionalidad en la elaboraci\u00f3n de artefactos e infraestructuras de  almacenamiento y funcionamiento energ\u00e9tico. Ahora bien, es parad\u00f3jico que a pesar de que la transici\u00f3n  sustentable es un fen\u00f3meno deseable a escala global, la extracci\u00f3n del Litio y de otros recursos y minerales  necesarios para realizar dicha transici\u00f3n, genere tensiones e impactos locales negativos.  \r\nEn la discusi\u00f3n p\u00fablica muchas veces emerge un discurso tecno-optimista, que posiciona a las tecnolog\u00edas  emergentes, como la soluci\u00f3n a estas controversias. Nuestra propuesta, sostiene que las tecnolog\u00edas denominadas  como emergentes, por s\u00ed mismas, sin un proceso de evaluaci\u00f3n, no necesariamente resolver\u00e1n las tensiones en  torno a la extracci\u00f3n y procesamiento de Litio. Por el contrario, argumentamos que se debe elaborar un sistema  de indicadores de estas tecnolog\u00edas emergentes que integre indicadores de desempe\u00f1o tecnol\u00f3gico y sociales ambientales construidos mediante procesos de participaci\u00f3n con las comunidades territorialmente situadas.  \r\nEn este contexto, existe una robusta literatura cient\u00edfica predominantemente retrospectiva que documenta los  impactos socioambientales de la extracci\u00f3n y procesamiento de Litio en Chile. Ahora bien, incluso a nivel  internacional existen pocos esfuerzos por comprender desde una perspectiva situada, cu\u00e1les son los posibles  impactos de la implementaci\u00f3n de tecnolog\u00edas emergentes en la extracci\u00f3n y procesamiento de Litio. As\u00ed, este trabajo propone un enfoque desde las Ciencias Sociales para abordar estas tecnolog\u00edas emergentes, que se nutre  de propuestas desde la Ingenier\u00eda, Sociolog\u00eda territorial y ambiental y el Management.  \r\nEl proyecto agrupa a las dos universidades m\u00e1s importantes de la Regi\u00f3n de Antofagasta y a la principal  universidad p\u00fablica-estatal del pa\u00eds, as\u00ed, el equipo se compone por investigadores e investigadoras de la  Universidad Cat\u00f3lica del Norte, Universidad de Antofagasta y Universidad de Chile. Atendiendo al requerimiento  de la Agencia Nacional de Investigaci\u00f3n y Desarrollo del Gobierno de Chile que en las bases concursales solicita  abordajes multidisciplinarios, el equipo cuenta con el aporte disciplinar de la Econom\u00eda, el Management, la  Sociolog\u00eda, la Ingenier\u00eda Qu\u00edmica, Ingenier\u00eda Industrial y Ciencias de la Tierra.  \r\nEsta propuesta de investigaci\u00f3n tiene como objetivo transferir un modelo para la implementaci\u00f3n de una  evaluaci\u00f3n socioambiental territorial para la potencial adopci\u00f3n de tecnolog\u00edas emergentes en la extracci\u00f3n y  procesamiento de litio a partir de salmueras en Chile. Los Objetivos Espec\u00edficos (O.E.) del proyecto son los  siguientes: i) Sistematizar el avance cient\u00edfico-comercial en tecnolog\u00edas convencionales y emergentes para la  extracci\u00f3n y procesamiento de litio desde salares, considerando sus distintas escalas de madurez y desempe\u00f1o  tecnol\u00f3gico; ii) Definir participativamente un conjunto de indicadores de sostenibilidad social y ambiental que  permitan evaluar las tecnolog\u00edas convencionales y emergentes para la extracci\u00f3n y procesamiento de litio desde  salares sistematizadas en el objetivo espec\u00edfico 1; iii) Dise\u00f1ar un modelo para la evaluaci\u00f3n de tecnolog\u00edas  emergentes con bajo impacto socioambiental para la industria del litio en Chile que contenga pol\u00edticas y  estrategias organizacionales basadas en el conjunto de indicadores territoriales definidos en el objetivo espec\u00edfico  2. Sustentados en la propuesta te\u00f3rica, metodol\u00f3gicamente se estructuran tres momentos en la investigaci\u00f3n, en  los cuales se emplean t\u00e9cnicas de recolecci\u00f3n y an\u00e1lisis de informaci\u00f3n cuantitativas y cualitativas. A nivel general,  estos momentos se encuentran articulados mediante sus productos, es decir, cada momento genera insumos para  el que contin\u00faa.  \r\nExiste una red de colaboraci\u00f3n internacional del proyecto, compuesta por LUT University de Finlandia, Bauhaus Weimar y University of Augsburg en Alemania, con los cuales se realizar\u00e1 colaboraci\u00f3n en investigaci\u00f3n y en  formaci\u00f3n de capital humano avanzado. Al mismo tiempo, se ha construido una ecosistema al proyecto,  compuesto por organizaciones no acad\u00e9micas, entre ellas, \u0093 SQM, Mesa t\u00e9cnica de la mesa multiactor del salar  de Atacama, Asociaci\u00f3n Atacame\u00f1a Regantes y Agricultores del R\u00edo Vilama y Fundaci\u00f3n Chile\u0094, quienes  participar\u00e1n como colaboradores activos en actividades de difusi\u00f3n, investigaci\u00f3n y transferencia del proyecto.  \r\nEste proyecto es un aporte y una contribuci\u00f3n cient\u00edfica al entendimiento de los procesos de innovaci\u00f3n y  evaluaci\u00f3n de tecnolog\u00edas emergentes en la extracci\u00f3n y procesamiento de Litio desde las Ciencias Sociales.  Tambi\u00e9n aporta a la sociedad, debido a que provee de un sistema de indicadores socioambientales elaborados en  base a participaci\u00f3n social, una evaluaci\u00f3n y sistematizaci\u00f3n de las tecnolog\u00edas que existe a nivel internacional y  un modelo de transferencia e innovaci\u00f3n enfocado en la industria del Litio. As\u00ed, sus resultados son relevantes para  la toma de decisiones actuales en Chile.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 24I10188<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2024 - Junio 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25987\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Herramienta molecular para el monitoreo de la sensibilidad farmacol\u00f3gica de productos antiparasitarios contra el piojo de mar en la industria salmonera\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25987\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25987\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo General\r\nDesarrollar un kit de qPCR que permita evaluar con precisi\u00f3n la sensibilidad farmacol\u00f3gica de C.\r\nrogercresseyi a tratamientos como inhibidores de quitina mediante asociaci\u00f3n estad\u00edstica entre\r\nfrecuencia de marcadores gen\u00f3micos y eficacia de tratamientos en campo.\r\n\r\nObjetivos Espec\u00edficos\r\n1. Validar estad\u00edsticamente la relaci\u00f3n entre las variantes gen\u00f3micas detectadas por el kit de\r\nqPCR y la resistencia a tratamientos con inhibidores de quitina.\r\n2. Establecer un protocolo de buenas pr\u00e1cticas de laboratorio para la correcta aplicaci\u00f3n del\r\nkit de qPCR.\r\n3. Implementar capacitaciones para laboratorios y culminar con la certificaci\u00f3n de aquellos\r\naptos para aplicar la t\u00e9cnica con eficacia.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 40059116<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26230\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia: Estrategia fitosanitaria para la producci\u00f3n sostenible de olivares en la regi\u00f3n de O\u0092Higgins.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26230\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26230\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En esta propuesta consideramos que la prospecci\u00f3n y detecci\u00f3n temprana de fitopat\u00f3genos\r\nconstituye una iniciativa altamente necesaria de abordar de una manera colaborativa e\r\nintegrada con los productores y otros integrantes del sistema oliv\u00edcola. Lo anterior, debido a\r\nque hay escaza informaci\u00f3n sobre los pat\u00f3genos bacterianos y virales que atacan al cultivo\r\ndel olivo en Chile, como as\u00ed tambi\u00e9n, de los insectos vectores que se asocian con la\r\ndiseminaci\u00f3n de estos. Por otra parte, la informaci\u00f3n disponible a nivel nacional se condice\r\ncon acciones aisladas y reactivas, es decir, que una vez se presenta el problema se act\u00faa en\r\nconsecuencia.\r\n&#61623; Realizar prospecciones colaborativas con actores del sistema productivo, peri\u00f3dicas y\r\npreventivas ser\u00e1n significativas para aplicar medidas de gesti\u00f3n y\/o manejo y cuarentena. En\r\nel hecho, la bacteria Xylella fastidiosa (agente causal del s\u00edndrome de declive r\u00e1pido del olivo;\r\nOQDS), se encuentra ausente para el cultivo del olivo en Chile, no obstante, existe un alto\r\nriesgo de ingreso y propagaci\u00f3n de esta bacteria si no se realiza una vigilancia activa, en\r\nparticular, del material de propagaci\u00f3n y en maquinaria agr\u00edcola que proviene de pa\u00edses\r\neuropeos donde el impacto de esta bacteria en olivos centenarios ha sido significativo, como\r\nlo ocurrido en la regi\u00f3n de Apulia (Italia).\r\n&#61623; Adquirir mayor informaci\u00f3n de como el cambio clim\u00e1tico acelerado impacta en la incidencia de\r\nenfermedades emergentes, y en fitopatogenos que se encuentran en estado de latencia en el\r\ncultivo del olivo. En este aspecto, se desconoce el efecto en la distribuci\u00f3n e impacto de\r\nmuchos fitopat\u00f3genos, lo que consideramos es de alto riesgo para la seguridad alimentaria y\r\nsostenibilidad de la producci\u00f3n, en este caso de la olivicultura y oleicultura.\r\n&#61623; Proveer de informaci\u00f3n relevante para sostener una total y profunda vigilancia que permita al\r\nSAG asegurar que la maquinaria agr\u00edcola que ingresa a territorio nacional, se encuentre exenta\r\nde material vegetal contaminado de procedencia. Para labores de cosecha se ha optado por\r\nel ingreso de maquinaria agr\u00edcola (regulado por normativas vigentes) proveniente de pa\u00edses\r\neuropeos (principalmente Espa\u00f1a) donde se ha reportado enfermedades asociadas a virus y\r\nbacterias fitopat\u00f3genas de car\u00e1cter cuarentenario para Chile; esta situaci\u00f3n involucra un alto\r\nriesgo para la sanidad de los olivos de la regi\u00f3n y del pa\u00eds.\r\n&#61623; Contribuir en informar y educar a los productores, asesores t\u00e9cnicos e identidades p\u00fablicas\r\nque forman parte del sistema productivo oliv\u00edcola de la regi\u00f3n de O\u0092Higgins en t\u00f3picos de\r\nfitosanidad del cultivo del olivo, entregar\u00e1 herramientas y mayor comprensi\u00f3n de los\r\nfen\u00f3menos asociados a la salud del olivo en condiciones locales. Por otra parte, los desaf\u00edos\r\nque deben resolver los productores en materia de fitosanidad pueden en algunas\r\noportunidades ser limitadas o deficientes por falta de informaci\u00f3n, y en consecuencia no\r\ndeterminar la estrategia o t\u00e1ctica m\u00e1s apropiada para el control de enfermedades en plantas.\r\n&#61623; Tambi\u00e9n, notamos del Diagnostico territorial participativo un gran inter\u00e9s por parte de los\r\nproductores en proteger la salud de sus olivos, a trav\u00e9s de la detecci\u00f3n temprana de problemas\r\nfitosanitarios que eviten una contaminaci\u00f3n masiva en olivos propios y vecinos.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FIC IDI 40059063-0<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2024 - Mayo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26314\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26314\" aria-expanded=\"false\" aria-controls=\"collapse-26314\">\n                                            Transferencia Aumento de la Competitividad para los rubros hort\u00edcola y ap\u00edcola de la Regi\u00f3n de O\u0092Higgins mediante el Sello Reducci\u00f3n de Riesgos Alimentarios (RRA)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26314\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26314\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivos espec\u00edficos:\r\nCapacitar a los productores ap\u00edcolas y hort\u00edcolas en cultura de inocuidad alimentaria y reglamento RRA en forma continua.\r\nCertificar a trav\u00e9s del sello RRA\r\nDesarrollar una campa\u00f1a de difusi\u00f3n y marketing regional del sello RRA.\r\nConformar el comit\u00e9 asesor p\u00fablico-privado regional de car\u00e1cter permanente para asesorar y apoyar el funcionamiento continuo del sello RRA.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FIC 40059072-0<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2024 - Mayo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26428\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia de un Programa de extensi\u00f3n e innovaci\u00f3n para la adaptaci\u00f3n de la apicultura al cambio clim\u00e1tico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26428\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26428\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetivo de este proyecto es generar una estrategia de extensi\u00f3n e innovaci\u00f3n, que permita la adaptaci\u00f3n de la apicultura al cambio clim\u00e1tico. Esta estrategia contempla 4 objetivos espec\u00edficos que permitir\u00e1n profesionalizar el rubro ap\u00edcola de la regi\u00f3n de O\u0092Higgins. El primer objetivo espec\u00edfico es entregar herramientas te\u00f3ricas a los apicultores a trav\u00e9s de cursos y talleres, tanto de manera online como presencial. El segundo objetivo espec\u00edfico es entregar herramientas pr\u00e1cticas, gracias a la implementaci\u00f3n de Unidades de Mejoramiento Productivo Ap\u00edcola, un Apiario Demostrativo y el Laboratorio de Apicultura. El tercer objetivo espec\u00edfico es desarrollar un an\u00e1lisis territorial que permita fortalecer el sistema de trazabilidad. Y el cuarto objetivo espec\u00edfico, es seguir fortaleciendo el capital social a trav\u00e9s de actividades vinculaci\u00f3n con entidades nacionales y\/o internacionales.\r\nEl proyecto tiene como resultado final, formar apicultores y actores de la cadena ap\u00edcola, capacitados para desarrollar las diferentes actividades necesarias en la producci\u00f3n ap\u00edcola. Estas capacidades integradas al conocimiento de los apicultores, les permitir\u00e1n realizar un manejo integral y resolver los problemas asociados al cambio clim\u00e1tico que enfrenten en el diario desempe\u00f1o de su profesi\u00f3n. Para ello se capacitar\u00e1n en aspectos te\u00f3ricos y pr\u00e1cticos. Se les entregar\u00e1n competencias laborales de conocimiento, actitudes y habilidades para que puedan cumplir de forma exitosa con las actividades de la funci\u00f3n ap\u00edcola, permitiendo a los apicultores profesionalizarse.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> IDI40059070-0<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2024 - Diciembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26561\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia Tecnol\u00f3gica 4.0 para la gesti\u00f3n del riesgo en la cadena de valor de la cereza\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26561\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26561\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto tiene como objetivo generar un impacto positivo en la cadena de valor de las cerezas, abarcando tanto las actividades primarias de operaci\u00f3n, labores agr\u00edcolas y estimaciones, as\u00ed como las actividades de apoyo para el desarrollo de tecnolog\u00edas. Se busca mejorar la toma de decisiones y la planificaci\u00f3n de la producci\u00f3n al\r\nproporcionar una herramienta para generar estimaciones de la producci\u00f3n basadas en los datos intraprediales, en contraposici\u00f3n a planificar \u00fanicamente con datos hist\u00f3ricos, teniendo en cuenta la variabilidad clim\u00e1tica en cada temporada. Esta herramienta tiene como enfoque aumentar la capacidad de planificaci\u00f3n del manejo del cultivo, y as\u00ed proporcionar informaci\u00f3n precisa a los asesores y servir de puente entre los productores y las exportadoras.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 40059111-0<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2024 - Mayo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26354\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            FIC Transferencia La Despensa de O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26354\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26354\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Garantizar la competitividad de los usuarios del sello La Despensa de O\u0092Higgins, mediante la disminuci\u00f3n de las brechas de producci\u00f3n, tecnol\u00f3gicas, redes y de capacitaci\u00f3n, para la obtenci\u00f3n de productos agroalimentarios con sello regional de calidad, tradici\u00f3n e innovaci\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26655\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            TRANSFERENCIA SUPERCOMPUTACI\u00d3N PARA INNOVACI\u00d3N EN SALUD REGIONAL: HPC-UOH Y HRLBO\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26655\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26655\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]TRANSFERENCIA SUPERCOMPUTACI\u00d3N PARA INNOVACI\u00d3N EN SALUD REGIONAL: HPC-UOH Y HRLBO[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26949\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            TRANSFERENCIA SUPERCOMPUTACI\u00d3N PARA INNOVACI\u00d3N EN SALUD REGIONAL: HPC-UOH Y HRLBO\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26949\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26949\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]TRANSFERENCIA SUPERCOMPUTACI\u00d3N PARA INNOVACI\u00d3N EN SALUD REGIONAL: HPC-UOH Y HRLBO[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27041\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            TRANSFERENCIA SUPERCOMPUTACI\u00d3N PARA INNOVACI\u00d3N EN SALUD REGIONAL: HPC-UOH Y HRLBO\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27041\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27041\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]TRANSFERENCIA SUPERCOMPUTACI\u00d3N PARA INNOVACI\u00d3N EN SALUD REGIONAL: HPC-UOH Y HRLBO[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26601\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Data-driven decision-making in Location and Transportation\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26601\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26601\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Decision-making processes involving uncertainty in the input parameters are commonplace, and the operational research community has investigated different methods to tackle this issue since the 60s. The current widespread availability of data and information presents a great opportunity to enhance the decision-making process, but at the same time, it presents a great challenge to develop new models and algorithms that capture this information. Stochastic programming, robust optimization, risk-averse optimization and distributionally robust optimization are different ways to deal with uncertainty. The input parameters are either modeled as random variables with a probability distribution that can be estimated from data; or as an uncertainty set which is often also decuded from data. A different approach is decision-focused learning or (a.k.a. smart predict-then-optimize) in which input parameters are learnt by a machine learning model which is trained considering the impact on the sub-opmality decisions made by not knowing perfectly the uncertain parameters. After training with this methodology, uncertain parameters are treated as deterministic parameters for the optimization problem. The main objective of this project is to provide a general framework for data-driven decision-making for different settings in transportation and logistics and to provide large-scale optimization models and algorithms to tackle uncertainty when data is available for these settings. We aim to compare and understand when each methodology to deal with uncertainty is the most adequate. Specifically, we aim to study problems in two-tier city logistics; large scale shortest path problems with real data motivated by firetruck dispatchment; multi-layer districting problems with balance constraint and uncertain demand; and the allocation security resources in a transportation network where the behavior of opportunistic passengers and the deployment of security agents are correlated.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ECOS230004<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2024 - Mayo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26871\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Volcanism in the Atacama Desert as an analog to Mars\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26871\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26871\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Pedir[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2024 - Enero 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26108\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Lenguaje y ciudad: el paisaje ling\u00fc\u00edstico para una did\u00e1ctica de la lengua con pertinencia territorial\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26108\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26108\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Esta propuesta tiene como objetivo implementar una metodolog\u00eda de ense\u00f1anza-aprendizaje\r\nvinculada al uso del espacio p\u00fablico como recurso formativo en cursos de lenguaje. Para ello,\r\nmovilizamos el concepto Paisaje Ling\u00fc\u00edstico (PL); esto es, la materializaci\u00f3n de las lenguas en el\r\nespacio p\u00fablico, a trav\u00e9s de los registros escritos que ah\u00ed encontramos. Se trata de una herramienta\r\ndid\u00e1ctica que posibilita desarrollar procesos formativos significativos y con pertinencia territorial.\r\nLa implementaci\u00f3n se har\u00e1 inicialmente en el curso Variaciones del Espa\u00f1ol de Pedagog\u00eda en\r\nLenguaje y Comunicaci\u00f3n e involucra un proceso de indagaci\u00f3n, registro fotogr\u00e1fico y an\u00e1lisis del\r\npaisaje ling\u00fc\u00edstico en la regi\u00f3n, con el objetivo de descubrir c\u00f3mo conviven lenguas y variedades\r\nen su diversidad y cu\u00e1nto aquello nos dice de nuestra vida en sociedad. El segundo semestre, en\r\ntanto, se espera implementar esta propuesta en el curso Introducci\u00f3n a la Gram\u00e1tica de Pedagog\u00eda\r\nen Educaci\u00f3n B\u00e1sica, con foco en ortograf\u00eda y morfolog\u00eda. El objetivo es promover la reflexi\u00f3n\r\nmetaling\u00fc\u00edstica junto con valorar la diversidad ling\u00fc\u00edstico-cultural de la regi\u00f3n en tanto expresi\u00f3n\r\nde identidades personales y sociales.\r\nUno de los hitos en este proyecto ser\u00e1 el montaje de una exhibici\u00f3n fotogr\u00e1fica guiada, cuyo\r\nprop\u00f3sito ser\u00e1 compartir los resultados de esta iniciativa en un espacio abierto a la comunidad, en\r\nlos campus Rancagua y Colchagua.\r\nPor \u00faltimo, y como instancia de cierre, se contempla la realizaci\u00f3n de dos jornadas en modalidad\r\nde taller en torno al PL tanto para otros docentes de la universidad como para profesoras\/es en\r\nformaci\u00f3n y en ejercicio.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 716140<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2024 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Fondart regional Ministerio de las culturas, las artes y el patrimonio<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26081\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Discurso visual e imagen sensible. Taller de fotograf\u00eda para j\u00f3venes escolares y adultos en la escuela de cultura y difusi\u00f3n art\u00edstica de Coltauco\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26081\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26081\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto busca inducir a los estudiantes de ense\u00f1anza media a realizar acciones exploratorias fotogr\u00e1ficas (actos con prop\u00f3sito) que permitan a la docente, en la medida que los estudiantes van Explorando\/Investigando, incorporar elementos t\u00e9cnicos que enriquezcan el proceso, se reflexione sobre los resultados y se produzcan soluciones visuales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 87212<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2024 - Abril 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio del Medi Ambiente<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26192\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Ra\u00edces Sostenibles: L\u00edderes Ambientales para la Acci\u00f3n Resiliente Local\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26192\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26192\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En el actual contexto de crisis planetaria y ante el notorio aumento de conflictos socioambientales, se reconoce la imperante\r\nnecesidad de fomentar una participaci\u00f3n activa por parte de las comunidades locales. El fundamento de nuestro modelo\r\nformativo no solo propicia la participaci\u00f3n de l\u00edderes ambientales, sino que tambi\u00e9n aspira a que estos l\u00edderes se conviertan en\r\nformadores de futuros l\u00edderes ambientales. El perfil y habilidades de las y los l\u00edderes ambientales, ser\u00e1n esenciales para ejercer\r\nun liderazgo positivo que pueda tener efectos favorables para nuestro medio ambiente. La literatura indica que l\u00edderes\r\nambientales efectivos e influyentes no s\u00f3lo consideran la preservaci\u00f3n del medioambiente en sus decisiones, sino que van m\u00e1s\r\nall\u00e1 del cumplimiento de normativas ambientales, asumiendo un papel activo y transformador. L\u00edderes ambientales efectivos\r\nmovilizan a otros a trav\u00e9s de la comunicaci\u00f3n, de sus motivaciones y conocimientos que las personas com\u00fanmente buscan en\r\nl\u00edderes. Si bien, lo que hace influyente a un l\u00edder depender\u00e1, en parte, de los problemas a resolver, cuando se trata de\r\nproblemas ambientales, las personas buscan l\u00edderes justos, con la experiencia y conocimientos necesarios, y efectivos a la hora\r\nde gestionar y accionar estrategias de cuidado del medioambiente. Los proyectos ambientales liderados por l\u00edderes en que las\r\npersonas conf\u00edan tienden a ser mejor recibidos por las comunidades. De manera similar, la investigaci\u00f3n sugiere que l\u00edderes\r\nambientales capaces de comunicar desaf\u00edos y urgencias ambientales, al tiempo que transmiten estrategias de abordaje para\r\nestos problemas, son m\u00e1s efectivos toda vez que proporcionan un sentido de urgencia, pero tambi\u00e9n la esperanza necesaria\r\npara evitar que personas y comunidades se sientan impotentes. Finalmente, l\u00edderes ambientales competentes o por prestigio\r\ngeneralmente son vistos como expertos, ya sea por conocimiento y\/o experiencia, y gozan de una buena reputaci\u00f3n buena\r\nreputaci\u00f3n debido a su compromiso de larga data con temas sociales.\r\nPara lograr lo anterior, el enfoque te\u00f3rico de nuestra propuesta apunta a la integraci\u00f3n del Modelo de Aprendizaje Experiencial\r\nde Kolb (2009). Este modelo, fundamentado en la teor\u00eda del aprendizaje experiencial, aporta una perspectiva valiosa para la\r\nformaci\u00f3n de l\u00edderes ambientales comunitarios que busca ofrecer una experiencia formativa din\u00e1mica que no solo transfiera\r\nconocimientos te\u00f3ricos, sino que tambi\u00e9n cultive habilidades pr\u00e1cticas para la acci\u00f3n en contextos locales. Para esto, se\r\nemplear\u00e1n estrategias did\u00e1cticas de situaciones reales de conflictos para favorecer el inter\u00e9s de los l\u00edderes en el desarrollo de\r\nlas actividades. Estas estrategias principalmente ser\u00e1n an\u00e1lisis de casos, juegos de rol, aprendizaje basado en problemas, e\r\nindagaci\u00f3n cient\u00edfica. Con el fin de favorecer el aprendizaje de los l\u00edderes ambientales, se considerar\u00e1 la teor\u00eda de aprendizaje\r\nde adultos que aborda tres grandes principios: la necesidad de aprender, para la cual se ha realizado una encuesta previa a\r\nl\u00edderes ambientales de la regi\u00f3n; el principio aplicable en la pr\u00e1ctica, que se desarrollar\u00e1 en cada m\u00f3dulo de aprendizaje del\r\nprograma; y, finalmente, el principio de reflexionar desde la experiencia y conocimientos, facilitado en cada sesi\u00f3n con\r\nreflexiones metacognitivas mientras se comparten experiencias para buscar soluciones conjuntas.\r\nFinalmente, el objetivo es influir en las pol\u00edticas p\u00fablicas, vinculando la participaci\u00f3n de las comunidades a temas\r\nmedioambientales. Un manual formativo permitir\u00e1 la aplicaci\u00f3n del programa en Chile, fortaleciendo la participaci\u00f3n ciudadana\r\nen liderazgos ambientales. La participaci\u00f3n ciudadana, junto con l\u00edderes, puede extenderse a trav\u00e9s de una red colaborativa a\r\nniveles regionales y nacionales, contribuyendo a la evaluaci\u00f3n de pol\u00edticas y decisiones para futuros sostenibles.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 23-MATH-13<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26653\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            SOGGA: Stochastic Optimization, Generalized Games and Applications\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26653\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26653\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El monto corresponde a 23500 EUR con tasa de conversi\u00f3n de 1022,47 CLP\/EUR. Este es el presupuesto asignado para el primer a\u00f1o.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FAPEG N\u00ba 04\/2024<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2024 - Mayo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Funda\u00e7\u00e3o de Amparo \u00e0 Pesquisa do Estado de Goi\u00e1s (FAPEG), Brasil<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27011\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27011\" aria-expanded=\"false\" aria-controls=\"collapse-27011\">\n                                            Coopera\u00e7\u00e3o entre pesquisadores do Instituto Federal Goiano (Brasil) e Universidade de O&#8217;Higgins (Chile), visando a internacionaliza\u00e7\u00e3o da P\u00f3s-Gradua\u00e7\u00e3o\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27011\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27011\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]O plano de desenvolvimento institucional do Estado de Goi\u00e1s prioriza a internacionaliza\u00e7\u00e3o da pesquisa e dos pesquisadores. A estrat\u00e9gia envolve integrar a ci\u00eancia produzida em Goi\u00e1s em redes de coopera\u00e7\u00e3o internacionais, promovendo colabora\u00e7\u00f5es que enriquecem o conhecimento e impulsionam a inova\u00e7\u00e3o. Nesse contexto, a visita do pesquisador internacional Dilier Olivera Viciedo da UOH, Chile em colaborac\u00e3o com a pesquisadora K\u00e1tia Aparecida de Pinho Costa do IF-Goiano, Brasil fortalecer\u00e1 os v\u00ednculos entre os pesquisadores, al\u00e9m de contribuir para a internacionaliza\u00e7\u00e3o dos programas de p\u00f3s-gradua\u00e7\u00e3o. A proposta em quest\u00e3o, na qual j\u00e1 h\u00e1 colabora\u00e7\u00e3o com o pesquisador, visa enfrentar desafios das mudan\u00e7as clim\u00e1ticas atrav\u00e9s da adapta\u00e7\u00e3o e mitiga\u00e7\u00e3o, estudando o desempenho de gram\u00edneas forrageiras sob aquecimento e inocula\u00e7\u00e3o bacteriana, contribuindo para a agricultura sustent\u00e1vel e a redu\u00e7\u00e3o de emiss\u00f5es de gases de efeito estufa. Durante sua estadia, o Prof. Dilier tamb\u00e9m buscar\u00e1 aprimorar metodologias de avalia\u00e7\u00e3o de forragem para promover a sustentabilidade no manejo de pastagens.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11241036<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2024 - Abril 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26150\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Assessing seasonal mobility of extinct proboscideans during the Last Glacial Termination in central Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26150\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26150\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Interpretar el paleoclima del Pleistoceno de Chile central[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 3240062<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2024 - Abril 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26564\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26564\" aria-expanded=\"false\" aria-controls=\"collapse-26564\">\n                                            Resultados de existencia y periodicidad de soluciones a EDPs locales y no-locales de tipo semilineal\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26564\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26564\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Esta propuesta est\u00e1 dedicada al estudio de problemas locales y no locales, el\u00edpticos y parab\u00f3licos, en Ecuaciones en Derivadas Parciales (EDP). Se espera obtener resultados de existencia para los problemas planteados, son 3 los problemas que se quieren estudiar: El primer modelo involucra al Laplaciano Fraccionario con singularidades no lineales (Ecuaci\u00f3n Fraccionaria de Burger ver (3)). En este problema queremos probar la existencia y la no unicidad de soluciones d\u00e9biles de (3), teniendo en cuenta que las soluciones de entrop\u00eda son soluciones d\u00e9biles, el primer paso ser\u00e1 probar existencia de soluciones de entrop\u00eda, para esto usaremos el m\u00e9todo de sub y supersoluciones, donde probaremos los resultados de los principios de Comparaci\u00f3n y L1-Contracci\u00f3n. Una vez teniendo la existencia de soluci\u00f3n de entrop\u00eda, pasaremos a construir una soluci\u00f3n d\u00e9bil que no sea soluci\u00f3n de entrop\u00eda, donde esta soluci\u00f3n d\u00e9bil se obtendr\u00e1 como l\u00edmite de soluciones a problemas regularizados estacionarios, en donde usaremos m\u00e9todos variacionales para resolver el problema regularizado.\r\nEl segundo problema, es una extensi\u00f3n al caso no local del problema estudiado en [L. Jeanjean and V. Radulescu, Nonhomogeneous quasilinear elliptic problems: linear and sublinear cases, Journal d'Analyse Math\u00e9matique (2021)]. Para probar existencia de soluciones aplicaremos estudios de m\u00ednimos locales y el teorema del paso de monta\u00f1a para el funcional de energ\u00eda asociado.\r\nPara finalizar nuestra propuesta, queremos encontrar soluciones peri\u00f3dicas para sistemas de EDP de cuarto orden (tipo Fisher-Kolmogorov generalizado, ver (9). Siguiendo las t\u00e9cnicas en [P. Smyrnelis, Connecting orbits in Hilbert Spaces and application to PDEs, Comm. Pure Appl Anal 19 (5):  2897--2818 (2020)], usaremos m\u00e9todos variacionales para probar la existencia de \u00f3rbitas conectadas en espacios de Hilbert. Construiremos \u00f3rbitas peri\u00f3dicas usando la construcci\u00f3n desarrollada por Alessio, Montecchiari y Z\u00fa\u00f1iga en [F. Alessio and P. Montecchiari and A. Zuniga, Prescribed energy connecting orbits for gradient systems, Discr. Cont. Dyn. Systems 39 (8): 4895--4928 (2019].[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Patrocinante<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2024 - Octubre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26621\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Integrative analysis of transcriptomic and metabolomic profiles in Citrullus lanatus grafted onto Lagenaria siceraria rootstocks in response to drought stress\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26621\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26621\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La sequ\u00eda representa m\u00e1s del 80% de los da\u00f1os y p\u00e9rdidas de los cultivos en todo el mundo. En la zona\r\nCentral de Chile se han presentado 9 a\u00f1os de sequ\u00eda ininterrumpida desde el 2010, con un d\u00e9ficit promedio\r\nde precipitaciones de 20 a 40%. Esto ha generado que el 88% de los agricultores de la zona central reporten\r\nun incremento en la ocurrencia de sequ\u00eda en sus cultivos, siendo este el principal estr\u00e9s abi\u00f3tico asociado a\r\nla p\u00e9rdida de cosechas y suministro sostenible de alimentos. La adaptaci\u00f3n o tolerancia al estr\u00e9s h\u00eddrico en\r\nlos cultivos, est\u00e1 asociada con la modificaci\u00f3n de diversas respuestas morfol\u00f3gicas y fisiol\u00f3gicas de las\r\nplantas, entre las que se incluyen cambios en el desarrollo del sistema radicular, ajustes en la tasa de\r\ncrecimiento, inducci\u00f3n del cierre de estomas, ajuste osm\u00f3tico, activaci\u00f3n de enzimas antioxidantes,\r\nacumulaci\u00f3n de fitohormonas y la regulaci\u00f3n transcripcional de muchos genes.\r\nLa sand\u00eda (Citrullus lanatus (Thunb.) Matsum. and Nakai) es una de las especies m\u00e1s cultivadas de la\r\nfamilia Cucurbitaceae, debido a su importancia econ\u00f3mica, alto valor nutricional y beneficios para la salud\r\n(por ejemplo, antioxidantes, carotenoides, citrulina, flavonoides, vitaminas (A, B y C) y minerales). La\r\nproducci\u00f3n mundial de sand\u00eda para el 2020 fue de 101.62 millones de toneladas aproximadamente, lo que\r\nla sit\u00faa como la segunda fruta fresca m\u00e1s producida a nivel mundial. Particularmente en Chile, en el a\u00f1o\r\n2020, la sand\u00eda fue la decimotercera fruta m\u00e1s producida (57,382 mil toneladas), siendo la regi\u00f3n de\r\nO\u0092Higgins la principal productora del pa\u00eds. El cultivo de sand\u00eda prospera mejor en \u00e1reas c\u00e1lidas, ya que\r\nrequiere altas temperaturas (>25\u00b0C) para un crecimiento \u00f3ptimo. Aunque la sand\u00eda prefiere un ambiente\r\nc\u00e1lido y seco, es conocida por su alta susceptibilidad al estr\u00e9s h\u00eddrico, por lo que su rendimiento est\u00e1 asociado\r\na la disponibilidad h\u00eddrica en la regi\u00f3n o \u00e1reas en que se cultive. En este sentido, una de las principales\r\nestrategias para reducir las p\u00e9rdidas de producci\u00f3n agr\u00edcola en condiciones de estr\u00e9s h\u00eddrico, es el cultivo de\r\nvariedades de alto rendimiento injert\u00e1ndolas en portainjertos tolerantes a este tipo de estr\u00e9s, con un sistema\r\nradicular eficiente en el uso del agua, como por ejemplo, Lagenaria siceraria. Particularmente, L. siceraria es\r\nuna especie perteneciente a la familia de las Cucurbitaceae, la cual es utilizada como portainjerto para el\r\ncultivo de la sand\u00eda, debido a que presenta resistencia a bajas temperaturas y enfermedades transmitidas a\r\nnivel de suelo (por ejemplo, Fusarium). Se ha informado que L. siceraria es m\u00e1s tolerante a la sequ\u00eda en\r\ncomparaci\u00f3n con otras cucurbit\u00e1ceas, ya que aumenta la absorci\u00f3n de agua y nutrientes del suelo, ayudando\r\nal crecimiento de las plantas. Sin embargo, el uso de L. siceraria como portainjerto de sand\u00eda para enfrentar\r\nel estr\u00e9s h\u00eddrico es limitado o nulo, particularmente existe desconocimiento de los mecanismos moleculares\r\npor el cual los portainjertos controlan el crecimiento de las plantas injertadas frente al estr\u00e9s.\r\nBajo condiciones de estr\u00e9s h\u00eddrico, las ra\u00edces son el primer \u00f3rgano que percibe la falta de agua en el\r\nsuelo, y comunican esta restricci\u00f3n como una se\u00f1al de estr\u00e9s a los brotes. En este sentido, se ha reportado\r\nque en injertos de solan\u00e1ceas y vit\u00e1ceas el portainjerto induce una reprogramaci\u00f3n transcripcional extensa\r\nen los brotes, especialmente de genes que participan en la transducci\u00f3n de se\u00f1ales de fitohormonas.\r\nParticularmente, el \u00c1cido Absc\u00edsico (ABA) desempe\u00f1a un papel fundamental en la regulaci\u00f3n del crecimiento\r\ny la defensa de las plantas en situaciones de estr\u00e9s h\u00eddrico, ya que se ha descrito como un integrador central\r\nque vincula y reprograma las complejas cascadas de se\u00f1alizaci\u00f3n adaptativa en respuesta al estr\u00e9s h\u00eddrico.\r\nSin embargo, ABA no es la \u00fanica fitohormona involucrada en la respuesta al estr\u00e9s h\u00eddrico, ya que se ha\r\ndescrito que otras fitohormonas, tales como, \u00e1cido salic\u00edlico, \u00e1cido jasm\u00f3nico y auxinas, est\u00e1n asociadas a la\r\nregulaci\u00f3n del crecimiento en condiciones de estr\u00e9s h\u00eddrico, interactuando entre ellos mismos y\/o con otros\r\nfactores. Por lo tanto, considerando lo se\u00f1alado anteriormente, se plantea la hip\u00f3tesis de que la tolerancia\r\nal estr\u00e9s h\u00eddrico en sand\u00eda injertada sobre L. siceraria est\u00e1 relacionada con el aumento en la expresi\u00f3n de\r\ngenes relacionados con la bios\u00edntesis, metabolismo y se\u00f1alizaci\u00f3n de ABA y otras fitohormonas en las hojas\r\ndel injerto C. lanatus y las ra\u00edces del portainjerto L. siceraria, lo cual confiere tolerancia al estr\u00e9s h\u00eddrico en\r\nC. lanatus. Cabe destacar que, los resultados generados en este estudio, contribuir\u00e1n a la comprensi\u00f3n de\r\nlas respuestas a la sequ\u00eda en las plantas, asociadas a diferentes fitohormonas, y servir\u00e1n como un recurso\r\np\u00fablico disponible para futuros estudios de expresi\u00f3n g\u00e9nica, gen\u00f3micos y funcionales de C. lanatus y L.\r\nsiceraria.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 3240293<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2024 - Abril 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27021\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Impacto del feedback y el feedforward digital en la producci\u00f3n de g\u00e9neros acad\u00e9micos por estudiantes de pedagog\u00eda en Lenguaje y Comunicaci\u00f3n\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27021\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27021\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Ingresar a la universidad supone el alcance de habilidades de escritura, ya que permite la integraci\u00f3n a una comunidad acad\u00e9mica y es la evaluaci\u00f3n de los aprendizajes disciplinares que se espera que los estudiantes adquieran. Sin embargo, son constantes las dificultades a las que los discentes deben enfrentarse no solo en el primer a\u00f1o de formaci\u00f3n, sino a lo largo de todo el grado acad\u00e9mico. El desarrollo de la escritura se ve altamente definido por la retroalimentaci\u00f3n que reciben los estudiantes. Al respecto, si bien existe una amplia tradici\u00f3n que aborda el feedback para proveer informaci\u00f3n al discente acerca de c\u00f3mo progresar en su escritura, son menos los estudios que abordan el feedforward, espec\u00edficamente el digital. En esta propuesta de investigaci\u00f3n postdoctoral se aborda la evaluaci\u00f3n a trav\u00e9s del feedback y feedforward en la producci\u00f3n de g\u00e9neros acad\u00e9micos de ingreso a la universidad, concretamente, en la carrera de Pedagog\u00eda en Lenguaje y Comunicaci\u00f3n.\r\nEn este contexto, el objetivo general de esta propuesta es describir la apropiaci\u00f3n del feedback y del feedforward digitales de los estudiantes de primer a\u00f1o de Pedagog\u00eda en Lenguaje y Comunicaci\u00f3n de la Universidad de O\u0092Higgins. A partir de una metodolog\u00eda mixta, se abordan la agencia de estudiantes de primer a\u00f1o y de sus profesores. Debido a que los datos que se espera obtener son diversos, se utilizar\u00e1n t\u00e9cnicas mixtas que incluyen el an\u00e1lisis de contenido y el an\u00e1lisis estad\u00edstico. Esta propuesta de investigaci\u00f3n postdoctoral contribuye al avance conceptual realizado por la investigadora previamente en relaci\u00f3n con la escritura acad\u00e9mica en contextos universitarios y su retroalimentaci\u00f3n. Los resultados esperados se vinculan a la discusi\u00f3n epistemol\u00f3gica y pr\u00e1ctica que conlleva el objeto de estudio: describir el feedback y feedforward digital en la producci\u00f3n escrita de un ensayo por estudiantes de pedagog\u00eda contribuir\u00e1 al desarrollo de oportunidades de aprendizaje y apropiaci\u00f3n de t\u00e9cnicas de evaluaci\u00f3n por parte\r\nde los profesores en formaci\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 3240062<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2024 - Abril 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27030\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27030\" aria-expanded=\"false\" aria-controls=\"collapse-27030\">\n                                            Resultados de existencia y periodicidad de soluciones a EDPs locales y no-locales de tipo semilineal\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27030\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27030\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Esta propuesta est\u00e1 dedicada al estudio de problemas locales y no locales, el\u00edpticos y parab\u00f3licos, en Ecuaciones en Derivadas Parciales (EDP). Se espera obtener resultados de existencia para los problemas planteados, son 3 los problemas que se quieren estudiar: El primer modelo involucra al Laplaciano Fraccionario con singularidades no lineales (Ecuaci\u00f3n Fraccionaria de Burger ver (3)). En este problema queremos probar la existencia y la no unicidad de soluciones d\u00e9biles de (3), teniendo en cuenta que las soluciones de entrop\u00eda son soluciones d\u00e9biles, el primer paso ser\u00e1 probar existencia de soluciones de entrop\u00eda, para esto usaremos el m\u00e9todo de sub y supersoluciones, donde probaremos los resultados de los principios de Comparaci\u00f3n y L1-Contracci\u00f3n. Una vez teniendo la existencia de soluci\u00f3n de entrop\u00eda, pasaremos a construir una soluci\u00f3n d\u00e9bil que no sea soluci\u00f3n de entrop\u00eda, donde esta soluci\u00f3n d\u00e9bil se obtendr\u00e1 como l\u00edmite de soluciones a problemas regularizados estacionarios, en donde usaremos m\u00e9todos variacionales para resolver el problema regularizado.\r\nEl segundo problema, es una extensi\u00f3n al caso no local del problema estudiado en [L. Jeanjean and V. Radulescu, Nonhomogeneous quasilinear elliptic problems: linear and sublinear cases, Journal d'Analyse Math\u00e9matique (2021)]. Para probar existencia de soluciones aplicaremos estudios de m\u00ednimos locales y el teorema del paso de monta\u00f1a para el funcional de energ\u00eda asociado.\r\nPara finalizar nuestra propuesta, queremos encontrar soluciones peri\u00f3dicas para sistemas de EDP de cuarto orden (tipo Fisher-Kolmogorov generalizado, ver (9). Siguiendo las t\u00e9cnicas en [P. Smyrnelis, Connecting orbits in Hilbert Spaces and application to PDEs, Comm. Pure Appl Anal 19 (5):  2897--2818 (2020)], usaremos m\u00e9todos variacionales para probar la existencia de \u00f3rbitas conectadas en espacios de Hilbert. Construiremos \u00f3rbitas peri\u00f3dicas usando la construcci\u00f3n desarrollada por Alessio, Montecchiari y Z\u00fa\u00f1iga en [F. Alessio and P. Montecchiari and A. Zuniga, Prescribed energy connecting orbits for gradient systems, Discr. Cont. Dyn. Systems 39 (8): 4895--4928 (2019].[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 3240004<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2024 - Abril 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27061\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fin al copago y a la selecci\u00f3n escolar: Efectos en la segregaci\u00f3n escolar, la matr\u00edcula p\u00fablica y la satisfacci\u00f3n de las familias\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27061\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27061\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Chile es un caso paradigm\u00e1tico en materia educacional, al ser uno de los pa\u00edses de la OECD con mayor provisi\u00f3n privada de educaci\u00f3n escolar y ser el caso m\u00e1s extremo de introducci\u00f3n de pol\u00edticas pro-mercado en educaci\u00f3n (Ladd y Fiske, 2020; OECD, 2020). Las bases del sistema educacional actual se asentaron con las reformas de los 80s durante la dictadura militar (1973-1990), donde se estableci\u00f3 un subsidio del tipo voucher a establecimientos municipales y privados subvencionados, que buscaba generar incentivos para mejorar la calidad educacional a nivel de sistema (Mizala y Torche, 2012). Los elementos centrales de una alta orientaci\u00f3n al mercado se mantuvieron durante los 90s y los 2000 (Canals et al., 2019), caracteriz\u00e1ndose el sistema por ser altamente segregado y segmentado (Lara, Mizala, y Repetto, 2011; Mizala y Torche, 2012; Valenzuela, Bellei, y R\u00edos, 2014). En este contexto, durante el segundo gobierno de Michelle Bachelet, se aprob\u00f3 la Ley de Inclusi\u00f3n Escolar, la cual busca disminuir el rol del mercado en la educaci\u00f3n (Bellei, 2016). Entre otras medidas, la ley establece el fin del cobro de mensualidad a los padres, y el fin de la selecci\u00f3n de estudiantes por parte de establecimientos p\u00fablicos y privados subvencionados (Ministerio de Educaci\u00f3n de Chile, 2019). Habiendo transcurridos 8 a\u00f1os desde la aprobaci\u00f3n de esta ley, este estudio tiene por objetivo analizar cu\u00e1les han sido y cu\u00e1les podr\u00edan ser los efectos esperados de mediano y largo plazo del fin de la selecci\u00f3n y el fin del copago en tres variables de inter\u00e9s: la segregaci\u00f3n escolar, la matr\u00edcula p\u00fablica y la satisfacci\u00f3n de las familias respecto al establecimiento educacional donde matriculan a sus hijos.\r\nCon este fin, se complementar\u00e1n dos estrategias metodol\u00f3gicas. En primer lugar, se estimar\u00e1n modelos econom\u00e9tricos para ahondar en los efectos que han tenido a la fecha el fin de la selecci\u00f3n escolar y la gradual eliminaci\u00f3n del copago -medida que a\u00fan no se ha aplicado totalmente. La gradualidad en la aplicaci\u00f3n de ambas medidas que establece la Ley de Inclusi\u00f3n es una ventaja en t\u00e9rminos de investigaci\u00f3n en tanto permite el monitoreo sistem\u00e1tico de los efectos de la ley, a la vez que facilita la identificaci\u00f3n de sus efectos mediante t\u00e9cnicas econom\u00e9tricas. En particular se estimar\u00e1 la segregaci\u00f3n escolar comunal a partir de indicadores de segregaci\u00f3n entre establecimientos, de segregaci\u00f3n entre sectores (p\u00fablico, privado subvencionado y privado pagado), y dentro de los sectores. Dichos indicadores ser\u00e1n estimados tanto para analizar la segregaci\u00f3n de los estudiantes del 40% m\u00e1s vulnerables (llamados prioritarios, desde la ley de Subvenci\u00f3n Escolar Preferencial), como del 20% de mayor nivel socioecon\u00f3mico. Luego, se estimar\u00e1n modelos de regresi\u00f3n y de efecto fijo a fin de estimar el efecto de ambas medidas en los distintos indicadores de segregaci\u00f3n. Similarmente, se estimar\u00e1n modelos de regresi\u00f3n y efecto fijo a fin de estimar el efecto de ambas medidas en el porcentaje de matr\u00edcula p\u00fablica a nivel comunal.\r\nEn segundo lugar, utilizaremos un modelo basado en agentes (ABM) que represente el sistema escolar chileno para estudiar los efectos del t\u00e9rmino del copago y selecci\u00f3n escolar en la satisfacci\u00f3n de las familias con el establecimiento educacional donde matricula a sus hijos\/as, y sus potenciales consecuencias en las tres variables de inter\u00e9s a mediano y largo plazo. Estudiar el efecto de estas medidas en la satisfacci\u00f3n de las familias a partir de t\u00e9cnicas econom\u00e9tricas es dif\u00edcil, ya que no contamos con informaci\u00f3n de cu\u00e1les eran las postulaciones de las familias previo a la reforma. A su vez, dado que la implementaci\u00f3n del fin del copago aun no es total, es dif\u00edcil analizar los efectos que tendr\u00e1 esta medida. Por ello, se utilizar\u00e1 modelamiento computacional para simular escenarios contrafactuales, permiti\u00e9ndonos analizar potenciales efectos que tendr\u00eda la total implementaci\u00f3n de la Ley de Inclusi\u00f3n en estos \u00e1mbitos. Los sistemas educacionales son complejos porque dependen de la interacci\u00f3n de much\u00edsimos agentes, son path-dependent, y est\u00e1n afectados por feedback loops (Ghaffarzadegan, Larson, & Hawley, 2017). Considerando estas caracter\u00edsticas, una metodolog\u00eda como los ABM permitir\u00e1 estudiar este sistema complejo, teniendo en cuenta los procesos de feedback e interacci\u00f3n que pueden hacer variar los efectos de esta ley en corto, mediano y largo plazo.\r\nEn t\u00e9rminos de resultados esperados, se espera contrastar tres hip\u00f3tesis de investigaci\u00f3n. En particular, a modo de hip\u00f3tesis, se considera que el fin del copago y de la selecci\u00f3n escolar en establecimientos p\u00fablicos y privados subvencionados i) propiciar\u00eda una menor segregaci\u00f3n de estudiantes prioritarios, pero un aumento de la segregaci\u00f3n de estudiantes de mayor nivel socioecon\u00f3mico, ii) generar\u00eda una disminuci\u00f3n de peque\u00f1a magnitud de la matr\u00edcula p\u00fablica y iii) aumentar\u00eda la satisfacci\u00f3n de las familias de estudiantes prioritarios respecto al establecimiento de matr\u00edcula, pero disminuir\u00eda levemente aquella de las familias de sectores medios (entre el 40% y 80% de vulnerabilidad socioecon\u00f3mica). Durante el desarrollo de esta investigaci\u00f3n, se espera difundir los hallazgos en esta materia a trav\u00e9s de la publicaci\u00f3n en revistas cient\u00edficas y presentaciones en congresos nacionales e internacionales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2024 - Marzo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25997\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            A Biopsychosocial Approach for Frailty Intervention: Uncovering a Circulating microRNA Biomarker Panel Using an Omics-Based Machine Learning Approach\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25997\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25997\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Frailty is increasingly becoming an important public health challenge worldwide because it is associated with older age, and with adverse outcomes such as reduced quality of life, increased mortality rates, hospitalizations, falls, depression, and dementia. Frailty is defined as dynamic state affecting an individual who experiences losses in one or more domains of human functioning (physical, psychological, social) that are caused by the influence of a range of variables, and which increases the risk of adverse outcomes. This more integral conceptual definition promotes the collaboration of scientists, social and behavioral professionals as well as clinicians from diverse specialties. In this proposal an interdisciplinary group (Biochemistry, Geriatric, Occupational Therapist, Kinesiologist, social worker, bioengineer, statistician among others) aims to evaluate frailty in Chile with a biopsychosocial approach with the final purpose to identify and manage frailty while taking into consideration all the dimensions. Additionally, we aim to design a multidomain personalized person-base intervention for a healthy aging that can uncover a circulating microRNA biomarker panel that can allow an early-detection of frailty, leading to a new multidimensional geriatric assessment. We propose the following hypothesis:  A personalized multidimensional training program reduces the frailty prevalence, increasing adherence and participation in the program among community-living older adults. This intervention will be paralleled by a distinctive miRNA profile reflecting the multiple domains of frailty, as well as improvements in diverse psychosocial traits.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2024 - Diciembre 2028<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>SeCyT<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26024\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Los procesos de ense\u00f1anza, integraci\u00f3n curricular, evaluaci\u00f3n y acreditaci\u00f3n en salud en grado y posgrado y su vinculaci\u00f3n con la trayectoria acad\u00e9mica y actividad docente\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26024\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26024\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Analizar los procesos de ense\u00f1anza, integraci\u00f3n curricular, evaluaci\u00f3n y acreditaci\u00f3n en carreras del \u00e1rea de salud en grado y posgrado y su relaci\u00f3n con la trayectoria acad\u00e9mica de los estudiantes y la actividad docente en Argentina y Chile.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2024 - Marzo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26132\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            A Biopsychosocial Approach for Frailty Intervention: Uncovering a Circulating microRNA Biomarker Panel Using an Omics-Based Machine Learning Approach\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26132\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26132\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Frailty is increasingly becoming an important public health challenge worldwide because it is associated with older age, and with adverse outcomes such as reduced quality of life, increased mortality rates, hospitalizations, falls, depression, and dementia. Frailty is defined as dynamic state affecting an individual who experiences losses in one or more domains of human functioning (physical, psychological, social) that are caused by the influence of a range of variables, and which increases the risk of adverse outcomes. This more integral conceptual definition promotes the collaboration of scientists, social and behavioral professionals as well as clinicians from diverse specialties. In this proposal an interdisciplinary group (Biochemistry, Geriatric, Occupational Therapist, Kinesiologist, social worker, bioengineer, statistician among others) aims to evaluate frailty in Chile with a biopsychosocial approach with the final purpose to identify and manage frailty while taking into consideration all the dimensions. Additionally, we aim to design a multidomain personalized person-base intervention for a healthy aging that can uncover a circulating microRNA biomarker panel that can allow an early-detection of frailty, leading to a new multidimensional geriatric assessment. We propose the following hypothesis:  A personalized multidimensional training program reduces the frailty prevalence, increasing adherence and participation in the program among community-living older adults. This intervention will be paralleled by a distinctive miRNA profile reflecting the multiple domains of frailty, as well as improvements in diverse psychosocial traits.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FIC400590730<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2024 - Marzo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26172\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            FIC-Editorial cooperativa para la publicaci\u00f3n de materiales educativos l\u00fadicos, de base cient\u00edfica y car\u00e1cter inclusivo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26172\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26172\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo general: Instalar una editorial cooperativa en la regi\u00f3n de O\u0092Higgins sustentada a partir de la comercializaci\u00f3n de productos y servicios educativos desarrollados en base a evidencia cient\u00edfica, que permitan implementar el aprendizaje basado en juegos y que consideran la diversidad del aula. Esta propuesta incluye la instalaci\u00f3n de un laboratorio de prototipado y producci\u00f3n, adem\u00e1s del desarrollo de un paquete de productos y servicios educativos cuya comercializaci\u00f3n permite sustentar la editorial cooperativa.\r\n5.4.1.\tObjetivo Espec\u00edfico 1 (Editorial Cooperativa)\r\nCoordinar una red de emprendedores del \u00e1rea educativa para establecer una editorial cooperativa para la Regi\u00f3n de O\u0092Higgins para desarrollar y comercializar productos y servicios educativos l\u00fadicos, de base cient\u00edfica y car\u00e1cter inclusivo. Funciona bajo un modelo de cooperativa cuyos miembros son emprendedores localizados en la regi\u00f3n de O\u0092Higgins con inter\u00e9s en innovaci\u00f3n educativa, trabajando bajo el principio de ayuda mutua.\r\n5.4.2.\tObjetivo Espec\u00edfico 2 (Diagn\u00f3stico de Productos)\r\nDiagnosticar las necesidades de productos y servicios educativos para promover la calidad de los aprendizajes en los primeros cursos de educaci\u00f3n b\u00e1sica en la regi\u00f3n de O\u0092Higgins. Identifica t\u00f3picos en matem\u00e1ticas y lenguaje que presentan dificultades al momento de su ense\u00f1anza, describe la diversidad de estudiantes en escuelas municipales e indaga m\u00e9todos de comercializaci\u00f3n comunes.\r\n5.4.3.\tObjetivo Espec\u00edfico 3 (Laboratorio de prototipado y Manufactura)\r\nInstalar en la Universidad de O\u0092Higgins un laboratorio para elaborar prototipos de  juegos de mesa educativos y producirlos en peque\u00f1a escala. Se adquiere maquinaria, equipamientos e insumos necesarios para que el Laboratorio de Aprendizaje Matem\u00e1tico (LAM) pueda prototipar juegos de mesa y, en conjunto con la F\u00e1brica Digital O\u0092Higgins (FabLab), producirlos con alta calidad y en peque\u00f1a escala de manera eficiente (30-100 ejemplares). \r\n5.4.4.\tObjetivo Espec\u00edfico 4 (Desarrollo de Productos)\r\nRealizar el dise\u00f1o, prototipado y manufactura de un paquete de productos educativos para fortalecer las \u00e1reas de matem\u00e1tica y lenguaje en los primeros a\u00f1os de educaci\u00f3n b\u00e1sica.  Dise\u00f1ados en base a ciencias del aprendizaje, estos productos permiten desarrollar aprendizajes en base a juegos y actividades l\u00fadicas considerando la diversidad de estudiantes en el aula.\r\n5.4.5.\tObjetivo Espec\u00edfico 5 (Capacitaci\u00f3n y Servicios)\r\nGenerar un programa de capacitaci\u00f3n para certificar a los emprendedores educativos para que provean servicios que acompa\u00f1an a los productos educativos ofrecidos por la editorial. Este programa certifica que el emprendedor es experto en la aplicaci\u00f3n de los productos educativos desarrollados. Este certificado habilita a los miembros de la editorial para ofrecer estos servicios en el mercado educativo.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1241626<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2024 - Marzo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26334\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            EPIGENOMIC PROGRAMMING IN THE EARLY FETAL BLOOD-BRAIN BARRIER BY GESTATIONAL  HYPOXIA: CONSEQUENCES FOR THE NEURO-ENDOTHELIAL LIFESPAN.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26334\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26334\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]EPIGENOMIC PROGRAMMING IN THE EARLY FETAL BLOOD-BRAIN BARRIER BY GESTATIONAL \r\nHYPOXIA: CONSEQUENCES FOR THE NEURO-ENDOTHELIAL LIFESPAN.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1241626<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26538\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            EPIGENOMIC PROGRAMMING IN THE EARLY FETAL BLOOD-BRAIN BARRIER BY GESTATIONAL HYPOXIA: CONSEQUENCES FOR THE NEURO-ENDOTHELIAL LIFESPAN\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26538\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26538\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The proposal focuses on understanding the neuro-vascular aging mechanisms associated with alterations in fetal growth by intrauterine hypoxia using molecular biology and physiology as an area. \r\nThe aim of the study is to demonstrate that impaired fetal growth conditions are associated with epigenetic programming of aging-related DNA methylation, chromatin remodeling, and miRNA-omic profile of junctional complex genes in the neuroendothelium, which can alter BBB integrity and permeability, increasing cerebral damage which impacts the juvenile and adulthood neurocognitive function.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2024 - Marzo 2028<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26548\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            1241726_Discursos de odio en redes sociales: Una aproximaci\u00f3n interdisciplinar para comprender el fen\u00f3meno y elaborar propuestas educomunicativas que fomenten la formaci\u00f3n de nuevas ciudadan\u00edas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26548\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26548\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Los tiempos actuales han facilitado nuevos medios de expresi\u00f3n e interacci\u00f3n como son las redes sociales. Estas plataformas, desde unos or\u00edgenes que bien podr\u00edan definirse como centrados en el entretenimiento, la comunicaci\u00f3n interpersonal y la puesta en com\u00fan de nuestra imagen e intereses, han pasado a convertirse en arenas de debates polarizados y nada edificantes.\r\nEn este escenario, nos parece necesario preguntarnos: \u00bfc\u00f3mo funciona la producci\u00f3n y circulaci\u00f3n cross-plataforma de discursos de odio en las redes sociales chilenas en los \u00faltimos a\u00f1os? Para obtener una respuesta, confiamos en que una aproximaci\u00f3n interdisciplinar emprendida por un equipo de comunicadores, ling\u00fcistas y cientistas de datos puede proporcionar una mirada m\u00e1s completa y compleja sobre este problema. Nuestro objetivo general es comprender el funcionamiento cross-plataforma de los discursos de odio producidos y puestos en circulaci\u00f3n en las redes sociales en Chile a partir de las tendencias informativas m\u00e1s relevantes entre 2015 y 2023. Para ello requerimos: 1) caracterizar cuantitativa y cualitativamente los tipos de discursos de odio producidos y puestos en circulaci\u00f3n en las redes sociales en Chile a partir de las tendencias informativas m\u00e1s relevantes entre 2015 y 2023; 2) identificar las cuentas de origen y diseminaci\u00f3n que hacen posible tanto la producci\u00f3n como la circulaci\u00f3n cross-plataforma de los tipos de discursos de odio y sus comentarios en las redes sociales en Chile, y; 3) analizar cualitativamente las estrategias ling\u00fc\u00edsticas y semi\u00f3ticas usadas sistem\u00e1ticamente en la producci\u00f3n de los tipos de discursos de odio y sus comentarios. Adem\u00e1s, y no menos importante, proponemos dise\u00f1ar un kit de recursos digitales con ejemplos y recomendaciones para fomentar estrategias de formaci\u00f3n ciudadana que ayuden a los\/as usuarios\/as de estas redes sociales a leer cr\u00edticamente los discursos de odio y proyectar acciones para confrontarlos o neutralizarlos. Si bien esta es una acci\u00f3n de divulgaci\u00f3n cient\u00edfica, nos parece necesario dar un peque\u00f1o paso que proyecte incluso futuras investigaciones aplicadas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2024 - Diciembre 2028<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>SeCyT<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26691\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Los procesos de ense\u00f1anza, integraci\u00f3n curricular, evaluaci\u00f3n y acreditaci\u00f3n en salud en grado y posgrado y su vinculaci\u00f3n con la trayectoria acad\u00e9mica y actividad docente\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26691\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26691\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Analizar los procesos de ense\u00f1anza, integraci\u00f3n curricular, evaluaci\u00f3n y acreditaci\u00f3n en carreras del \u00e1rea de salud en grado y posgrado y su relaci\u00f3n con la trayectoria acad\u00e9mica de los estudiantes y la actividad docente en Argentina y Chile.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Patrocinante<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FIC400590730<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2024 - Marzo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26699\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            FIC-Editorial cooperativa para la publicaci\u00f3n de materiales educativos l\u00fadicos, de base cient\u00edfica y car\u00e1cter inclusivo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26699\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26699\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo general: Instalar una editorial cooperativa en la regi\u00f3n de O\u0092Higgins sustentada a partir de la comercializaci\u00f3n de productos y servicios educativos desarrollados en base a evidencia cient\u00edfica, que permitan implementar el aprendizaje basado en juegos y que consideran la diversidad del aula. Esta propuesta incluye la instalaci\u00f3n de un laboratorio de prototipado y producci\u00f3n, adem\u00e1s del desarrollo de un paquete de productos y servicios educativos cuya comercializaci\u00f3n permite sustentar la editorial cooperativa.\r\n5.4.1.\tObjetivo Espec\u00edfico 1 (Editorial Cooperativa)\r\nCoordinar una red de emprendedores del \u00e1rea educativa para establecer una editorial cooperativa para la Regi\u00f3n de O\u0092Higgins para desarrollar y comercializar productos y servicios educativos l\u00fadicos, de base cient\u00edfica y car\u00e1cter inclusivo. Funciona bajo un modelo de cooperativa cuyos miembros son emprendedores localizados en la regi\u00f3n de O\u0092Higgins con inter\u00e9s en innovaci\u00f3n educativa, trabajando bajo el principio de ayuda mutua.\r\n5.4.2.\tObjetivo Espec\u00edfico 2 (Diagn\u00f3stico de Productos)\r\nDiagnosticar las necesidades de productos y servicios educativos para promover la calidad de los aprendizajes en los primeros cursos de educaci\u00f3n b\u00e1sica en la regi\u00f3n de O\u0092Higgins. Identifica t\u00f3picos en matem\u00e1ticas y lenguaje que presentan dificultades al momento de su ense\u00f1anza, describe la diversidad de estudiantes en escuelas municipales e indaga m\u00e9todos de comercializaci\u00f3n comunes.\r\n5.4.3.\tObjetivo Espec\u00edfico 3 (Laboratorio de prototipado y Manufactura)\r\nInstalar en la Universidad de O\u0092Higgins un laboratorio para elaborar prototipos de  juegos de mesa educativos y producirlos en peque\u00f1a escala. Se adquiere maquinaria, equipamientos e insumos necesarios para que el Laboratorio de Aprendizaje Matem\u00e1tico (LAM) pueda prototipar juegos de mesa y, en conjunto con la F\u00e1brica Digital O\u0092Higgins (FabLab), producirlos con alta calidad y en peque\u00f1a escala de manera eficiente (30-100 ejemplares). \r\n5.4.4.\tObjetivo Espec\u00edfico 4 (Desarrollo de Productos)\r\nRealizar el dise\u00f1o, prototipado y manufactura de un paquete de productos educativos para fortalecer las \u00e1reas de matem\u00e1tica y lenguaje en los primeros a\u00f1os de educaci\u00f3n b\u00e1sica.  Dise\u00f1ados en base a ciencias del aprendizaje, estos productos permiten desarrollar aprendizajes en base a juegos y actividades l\u00fadicas considerando la diversidad de estudiantes en el aula.\r\n5.4.5.\tObjetivo Espec\u00edfico 5 (Capacitaci\u00f3n y Servicios)\r\nGenerar un programa de capacitaci\u00f3n para certificar a los emprendedores educativos para que provean servicios que acompa\u00f1an a los productos educativos ofrecidos por la editorial. Este programa certifica que el emprendedor es experto en la aplicaci\u00f3n de los productos educativos desarrollados. Este certificado habilita a los miembros de la editorial para ofrecer estos servicios en el mercado educativo.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26775\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Effect of microplastics on soils from different land use types: assessing their interaction with metal(loid)s and effects on soil microbial communities under realistic conditions\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26775\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26775\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Microplastics (MPs) are plastic particles that range in size from 0.1 &#956;m to 5 mm. They have received widespread attention in the global environmental science community due to their potential effects on living organisms, ecosystem pollution, low recycling rate, and interaction with organic and inorganic contaminants. Although much research has been focused on MPs in aquatic ecosystems, terrestrial ecosystems have been largely overlooked. Consequently, there is still scarce knowledge on the sources and occurrence of MPs in soils. After being deposited in soil, MPs undergo an aging process that involves the breakdown of their polymeric chains, which promotes the interaction between MPs and organic and inorganic contaminants. This process further increases the toxicity of MPs when they sorb pollutants from the environment, which can be transported to water bodies and living organisms. However, research regarding the aging of MPs and their toxicity is needed since previous studies do not consider realistic soil conditions. Additionally, interactions between MPs and pollutants have been primarily studied for conventional MPs, with scarce research on such topics for degradable MPs, especially concerning interactions with metal(loid)s. In general, the interaction of degradable MPs with other contaminants and their further toxicity have been overlooked.\r\n\r\nMPs have been shown to negatively affect some physical, chemical, and biological soil properties. However, results varied between studies, which have been associated with the type and shape of MPs, soil aggregate structure, porosity, water and oxygen availability, among others. More research is needed to confirm such relationships in soils. Previous studies have been mainly performed in Europe and Asia, with scarce research in Latin America. In Chile, only one study has been conducted on MPs in soils at field conditions, with other two studies regarding the effect of MPs and metals on soil biochemical properties under controlled environments. Therefore, considerable efforts should be taken to study MPs in Chilean soils. Thus, this study aims to address these gaps by considering some realistic approaches that are missing from current research on MPs. Specifically, this research will: 1) assess MPs in soils from different land uses and examine their association with soil properties; 2) evaluate degradable MPs; 3) study the ageing and adsorption capability of different MPs to metal(loid)s in soils; and 4) investigate the interactive effect of MPs and metal(loid)s under realistic conditions (including a real dose of MPs and metal(loid)s, temperature fluctuations, and soils from different land use types). By taking these steps, this study will provide novel insights into the occurrence of MPs in Chilean soils and shed light on the dynamics of soil microbial communities in the presence of MPs and metal(loid)s.\r\n\r\nBased on the above, the proposed research aims to evaluate the effect of different types of MPs and their interaction with metal(loid)s on the soil community structure and functionality from different land use types under realistic conditions. The hypothesis is that MPs will negatively affect soil microbiome structure and functionality due to changes in soil physicochemical properties, which will be moderated by changes in the type, doses, ageing of MPs and their interactions with metal(loid)s in soil from different land type uses. This proposal will be conducted in the O\u0092Higgins Region (VI) of Chile. Firstly, in Phase 1, six localities from different land use types will be selected: an urban wetland, agricultural field, and sclerophyll forest. Soil samples will be taken to quantify and characterize the types of MPs in soil. Secondly, in Phase 2, the evaluation of different types of aging of MPs (conventional and degradable) on chemical characteristics of such particles will be performed, which is based on the ability of MPs as carriers of metal(loid)s. With information and soils obtained from Phase 1, a realistic experimental approach will be performed in the Phase 3. These include the evaluation of aged MPs (degradable and non-degradable) on soil physicochemical and biochemical properties, and the study of degradable and non-degradable aged MPs with metal(loid)s on the functionality, structure, and co-occurrence patterns of soil microbial communities. These phases are designed to be performed over three years. This is the first study focused on the evaluation the effect of MPs and metal(loid)s on microbial communities of soils from different land use types in Chile.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2024 - Diciembre 2028<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>SeCyT<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26843\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Los procesos de ense\u00f1anza, integraci\u00f3n curricular, evaluaci\u00f3n y acreditaci\u00f3n en salud en grado y posgrado y su vinculaci\u00f3n con la trayectoria acad\u00e9mica y actividad docente\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26843\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26843\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Analizar los procesos de ense\u00f1anza, integraci\u00f3n curricular, evaluaci\u00f3n y acreditaci\u00f3n en carreras del \u00e1rea de salud en grado y posgrado y su relaci\u00f3n con la trayectoria acad\u00e9mica de los estudiantes y la actividad docente en Argentina y Chile.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FIC400590730<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2024 - Marzo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26880\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            FIC-Editorial cooperativa para la publicaci\u00f3n de materiales educativos l\u00fadicos, de base cient\u00edfica y car\u00e1cter inclusivo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26880\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26880\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo general: Instalar una editorial cooperativa en la regi\u00f3n de O\u0092Higgins sustentada a partir de la comercializaci\u00f3n de productos y servicios educativos desarrollados en base a evidencia cient\u00edfica, que permitan implementar el aprendizaje basado en juegos y que consideran la diversidad del aula. Esta propuesta incluye la instalaci\u00f3n de un laboratorio de prototipado y producci\u00f3n, adem\u00e1s del desarrollo de un paquete de productos y servicios educativos cuya comercializaci\u00f3n permite sustentar la editorial cooperativa.\r\n5.4.1.\tObjetivo Espec\u00edfico 1 (Editorial Cooperativa)\r\nCoordinar una red de emprendedores del \u00e1rea educativa para establecer una editorial cooperativa para la Regi\u00f3n de O\u0092Higgins para desarrollar y comercializar productos y servicios educativos l\u00fadicos, de base cient\u00edfica y car\u00e1cter inclusivo. Funciona bajo un modelo de cooperativa cuyos miembros son emprendedores localizados en la regi\u00f3n de O\u0092Higgins con inter\u00e9s en innovaci\u00f3n educativa, trabajando bajo el principio de ayuda mutua.\r\n5.4.2.\tObjetivo Espec\u00edfico 2 (Diagn\u00f3stico de Productos)\r\nDiagnosticar las necesidades de productos y servicios educativos para promover la calidad de los aprendizajes en los primeros cursos de educaci\u00f3n b\u00e1sica en la regi\u00f3n de O\u0092Higgins. Identifica t\u00f3picos en matem\u00e1ticas y lenguaje que presentan dificultades al momento de su ense\u00f1anza, describe la diversidad de estudiantes en escuelas municipales e indaga m\u00e9todos de comercializaci\u00f3n comunes.\r\n5.4.3.\tObjetivo Espec\u00edfico 3 (Laboratorio de prototipado y Manufactura)\r\nInstalar en la Universidad de O\u0092Higgins un laboratorio para elaborar prototipos de  juegos de mesa educativos y producirlos en peque\u00f1a escala. Se adquiere maquinaria, equipamientos e insumos necesarios para que el Laboratorio de Aprendizaje Matem\u00e1tico (LAM) pueda prototipar juegos de mesa y, en conjunto con la F\u00e1brica Digital O\u0092Higgins (FabLab), producirlos con alta calidad y en peque\u00f1a escala de manera eficiente (30-100 ejemplares). \r\n5.4.4.\tObjetivo Espec\u00edfico 4 (Desarrollo de Productos)\r\nRealizar el dise\u00f1o, prototipado y manufactura de un paquete de productos educativos para fortalecer las \u00e1reas de matem\u00e1tica y lenguaje en los primeros a\u00f1os de educaci\u00f3n b\u00e1sica.  Dise\u00f1ados en base a ciencias del aprendizaje, estos productos permiten desarrollar aprendizajes en base a juegos y actividades l\u00fadicas considerando la diversidad de estudiantes en el aula.\r\n5.4.5.\tObjetivo Espec\u00edfico 5 (Capacitaci\u00f3n y Servicios)\r\nGenerar un programa de capacitaci\u00f3n para certificar a los emprendedores educativos para que provean servicios que acompa\u00f1an a los productos educativos ofrecidos por la editorial. Este programa certifica que el emprendedor es experto en la aplicaci\u00f3n de los productos educativos desarrollados. Este certificado habilita a los miembros de la editorial para ofrecer estos servicios en el mercado educativo.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1240579<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2024 - Marzo 2028<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26902\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Exploring and elucidating the interplays between dissolved organic matter and microbial communities along an aquatic continuum: from the Andes to the ocean\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26902\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26902\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Exploring and elucidating the interplays between dissolved organic matter and microbial communities along an aquatic continuum: from the Andes to the ocean[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2024 - Marzo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27032\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            A Biopsychosocial Approach for Frailty Intervention: Uncovering a Circulating microRNA Biomarker Panel Using an Omics-Based Machine Learning Approach\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27032\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27032\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Frailty is increasingly becoming an important public health challenge worldwide because it is associated with older age, and with adverse outcomes such as reduced quality of life, increased mortality rates, hospitalizations, falls, depression, and dementia. Frailty is defined as dynamic state affecting an individual who experiences losses in one or more domains of human functioning (physical, psychological, social) that are caused by the influence of a range of variables, and which increases the risk of adverse outcomes. This more integral conceptual definition promotes the collaboration of scientists, social and behavioral professionals as well as clinicians from diverse specialties. In this proposal an interdisciplinary group (Biochemistry, Geriatric, Occupational Therapist, Kinesiologist, social worker, bioengineer, statistician among others) aims to evaluate frailty in Chile with a biopsychosocial approach with the final purpose to identify and manage frailty while taking into consideration all the dimensions. Additionally, we aim to design a multidomain personalized person-base intervention for a healthy aging that can uncover a circulating microRNA biomarker panel that can allow an early-detection of frailty, leading to a new multidimensional geriatric assessment. We propose the following hypothesis:  A personalized multidimensional training program reduces the frailty prevalence, increasing adherence and participation in the program among community-living older adults. This intervention will be paralleled by a distinctive miRNA profile reflecting the multiple domains of frailty, as well as improvements in diverse psychosocial traits.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2024 - Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27058\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Segregaci\u00f3n de g\u00e9nero en la educaci\u00f3n media y superior chilena:  An\u00e1lisis de sus consecuencias en las brechas salariale\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27058\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27058\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Concurso RIS de Investigaci\u00f3n, Segregaci\u00f3n de g\u00e9nero en la educaci\u00f3n media y superior chilena:  An\u00e1lisis de sus consecuencias en las brechas salariales. Investigadora responsable: Lorena Ortega. Coinvestigadores: Catalina Canals y Alejandra Mizala (concurso adjudicado).[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1241649<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27069\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            DICATIONIC DERIVATIVES OF AZOBENZENE AS PHOTOACTIVE SURFACTANTS FOR DRUG TRANSPORT SYSTEMS: STUDY OF PHOTOREVERSIBLE BEHAVIOR AND LOAD CAPACITY IN MOLECULAR AGGREGATES\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27069\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27069\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]This project aims to investigate how structural modifications of a dicationic derivative of azobenzene can\r\naffect the drug release and load capacity of its photoactive molecular aggregate.\r\nTo evaluate this, three types of structural modifications are proposed. First, the introduction of functional\r\ngroups on the photoactive nucleus of dicationic azobenzene is expected to shift the absorption band of the\r\nmolecular photoswitch.\r\nSecond, the replacement of the fluorescent organic cations over the structure of the molecular\r\nphotoswitch, which confer luminescent and amphipathic properties to the system.\r\nAnd third, the modification of the length of the chains over the molecular photoswitch could change the\r\naggregate size.\r\nTo determine whether these potential modifications can modulate the light-induced release activity of the\r\nphotoswitchable aggregate, an enzyme inhibitor will be loaded and released by illumination in the presence\r\nof the enzyme.\r\nUnder this scenario, any modification of the enzymatic activity will be correlated with the drug's\r\nphotorelease.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11240512<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024 - Marzo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26427\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Chilean Honey Hydrogel: a novel antimicrobial against staphylococcus pseudintermedius and wound healing biomaterial\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26427\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26427\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Se propone estudiar la miel org\u00e1nica monofloral de Quillay (Quillaja saponaria Molina), que es un \u00e1rbol end\u00e9mico de Chile central. La miel de Quillay es reconocida por sus caracter\u00edsticas organol\u00e9pticas y efectos biol\u00f3gicos, comparables a mieles como la miel de manuka. Esta miel junto con el quitosano y la gelatina se utilizar\u00e1n para elaborar los hidrogeles. La CHH se esterilizar\u00e1 mediante radiaci\u00f3n gamma para obtener miel de grado m\u00e9dico. A continuaci\u00f3n, se estudiar\u00e1 la caracterizaci\u00f3n fisicoqu\u00edmica de la CHH y su efecto in vitro e in vivo. La caracterizaci\u00f3n se llevar\u00e1 a cabo mediante la determinaci\u00f3n de diferentes par\u00e1metros fisicoqu\u00edmicos y por cromatograf\u00eda l\u00edquida de ultra alto rendimiento-espectrometr\u00eda de masas. Tambi\u00e9n se determinar\u00e1 la capacidad antioxidante de la CHH. Tras esta caracterizaci\u00f3n qu\u00edmica, se evaluar\u00e1 in vitro el perfil de eficacia y seguridad de la miel. Para ello, se medir\u00e1 el efecto de la CHH sobre macr\u00f3fagos, fibroblastos y S. pseudintermedius. Por \u00faltimo, se comprobar\u00e1 el efecto in vivo de esta formulaci\u00f3n sobre la cicatrizaci\u00f3n de heridas en ratones. Para ello, se realizar\u00e1 un ensayo de cicatrizaci\u00f3n de heridas, junto con el an\u00e1lisis histopatol\u00f3gico de biopsias de heridas y la determinaci\u00f3n de par\u00e1metros hematol\u00f3gicos, para evaluar los cambios locales y sist\u00e9micos en los animales objeto de estudio. Con este proyecto, esperamos verificar y obtener nueva informaci\u00f3n sobre la capacidad de cicatrizaci\u00f3n de la miel chilena aplicada en hidrogeles en heridas infectadas por S. pseudintermedius. Esto permitir\u00e1 contar con m\u00e1s herramientas para tratar eficientemente este tipo de patolog\u00edas en medicina veterinaria.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024 - Marzo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26512\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desarrollo desigual y la pol\u00edtica del riesgo de desastres: Hacia una resiliencia justa en el Chile post-estallido\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26512\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26512\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Esta investigaci\u00f3n se enmarca en discusiones del campo interdisciplinario de los estudios de desastre, contribuyendo a la comprensi\u00f3n del rol de las comunidades en la gobernanza del riesgo. Estando establecido que los desastres relacionados con amenazas naturales se explican por la vulnerabilidad social, diversas agendas de desarrollo promueven pol\u00edticas que prevengan futuros eventos mediante la reducci\u00f3n de la vulnerabilidad o el aumento de la resiliencia. A pesar de esto, diversos grupos sociales no solo son mayormente afectados por desastres seg\u00fan su clase, g\u00e9nero, etnia\/raza, ubicaci\u00f3n, etc., sino adem\u00e1s son excluidos de las instancias formales de gesti\u00f3n del riesgo. Los desastres en definitiva son pol\u00edticos y expresan din\u00e1micas de desarrollo desigual.\r\n\r\nComo respuesta, habitantes de territorios en riesgo deben organizar iniciativas que permitan resistir y hacer frente a posibles desastres, incrementando su propia resiliencia. Al igual que los desastres y sus riesgos subyacentes, estas iniciativas se inscriben en el contexto social y pol\u00edtico m\u00e1s amplio. Sin embargo, no sabemos c\u00f3mo ciertas crisis y transformaciones sociales m\u00e1s amplias influyen en estas iniciativas de resiliencia. Esta investigaci\u00f3n se centra en Chile y el fen\u00f3meno denominado estallido social. Aunque el proceso abierto por el estallido, con sus movilizaciones y discursos cr\u00edticos, abr\u00eda la posibilidad de un nuevo escenario pol\u00edtico en el pa\u00eds, actualmente esto est\u00e1 en entredicho. A pesar de ello, es de suma relevancia analizar si este contexto influye en c\u00f3mo se gobiernan los riesgos en territorios expuestos a amenazas naturales. Es decir, si del estallido social emergi\u00f3 un conjunto de demandas por mayor justicia social y ambiental, es fundamental entender si tales discursos y pr\u00e1cticas interact\u00faan (o no) con iniciativas locales que potencien una resiliencia justa que promueva la igualdad y sustentabilidad territorial. Por ello, el objetivo general del proyecto es: Analizar c\u00f3mo los habitantes de territorios en riesgo experimentaron el estallido social, y c\u00f3mo esta experiencia influencia la organizaci\u00f3n y el funcionamiento de iniciativas colectivas de resiliencia justa.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11240017<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26536\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Role of cholesterol in brain vascular development of mouse embryos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26536\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26536\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The brain is an energy intensive organ that requires a robust supply of nutrients and oxygen. The vasculature irrigating the brain is a huge and complex network of blood vessels fulfilling this requirement, while also protecting the neural tissue from blood-borne toxic substances. This regulated nutrient supply is accomplished by the formation of a highly selective molecular barrier, termed the blood-brain barrier (BBB). Dysfunction of the BBB or malformations of the vascular network are associated with pathological conditions that impair brain function, and can lead to death. Thus, appropriate morphogenesis and establishment of the brain vasculature is necessary for a healthy life. \r\nThe brain vasculature forms during intrauterine development, matching brain growth in this same period. Anatomically, blood vessels grow first surrounding the brain primordium and then penetrate the parenchyma until they vascularize the periventricular zone. The molecular regulation of this patterned growth is not completely understood. Several signaling pathways are known to be involved in brain angiogenesis, including WNT, TGF-&#946;, Hh, and NOTCH, which differentially regulate vascular growth. Recently, cholesterol has been shown to modulate angiogenic growth in other vascular beds by regulating the activity of the NOTCH pathway, suggesting that cholesterol levels could influence developmental angiogenesis in the brain. Interestingly, cholesterol is also required for signal transduction of the Hh pathway. In preliminary in vitro experiments, we have observed that brain endothelial cells activate an angiogenic program after cholesterol depletion. Here, we will extend those studies to in vivo models to determine the role of cholesterol in developmental brain angiogenesis. We propose that an increase in vascular cell cholesterol activates NOTCH and attenuates Hh signaling pathways, restricting sprouting angiogenesis and blood-brain barrier formation in mouse embryo brain vasculature. \r\nTo test this hypothesis, we will study mouse embryos with altered cholesterol levels by dietary, pharmacological, and genetic manipulations. We expect these manipulations to induce a reduction or an increase in cholesterol levels in the brain vasculature during embryonic development, which we will evaluate by measuring cholesterol content in isolated vascular fragments. \r\nIn all these models, we will (Specific aim 1) study vascularization in the brain during intrauterine development using immunofluorescence with specific antibodies against endothelium proteins. In addition, we will measure the levels of transcript and proteins of general key regulators of angiogenesis in isolated vascular fragments, using qPCR and Western blot. We will (Specific aim 2) also evaluate the state of the BBB in the brain vasculature of these models at a fetal stage when the barrier is already formed and functional. For this, we will use immunofluorescence to detect the presence of marker proteins of the BBB in vascular fragments, and we will measure their levels by Western blot. Further, we will test the functionality of the barrier by injecting a fluorescent tracer and evaluating its extravasation in the brain. Finally, we will (Specific aim 3) determine the activation of the NOTCH and Hh pathways in the brain vasculature of the models at the stage of maximal angiogenesis. We will use qPCR and Western blot to measure the levels of marker genes and proteins for these two pathways in vascular fragments, and Proximity Ligation In Situ Hybridization in tissue sections to evaluate the transcript levels of those markers in situ. \r\nWe expect that the different models of dietary, pharmacological, and genetic interventions will increase or reduce cholesterol levels in the brain vasculature. These changes are expected to correlate with opposing effects on angiogenesis in the brain during development (i.e. low cholesterol will increase angiogenesis, while high cholesterol will inhibit it). In the same way, we expect that distinct cholesterol levels will have opposing effects on the integrity of the BBB. These changes in angiogenesis and BBB function are expected to be associated with concomitant disruption of the NOTCH and Hh pathways.\r\nIn summary, in this proposal we aim to cover a knowledge gap regarding the role of cholesterol in the regulation of developmental angiogenesis in the brain. These experiments may uncover new mechanisms driving vascular growth and barrier establishment in the brain, which could lead to new strategies for the prevention and treatment of pathologies involving the brain vasculature.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024 - Marzo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26858\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Is Easter Island (Rapa Nui) still active? Following the traces of its recent volcanism\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26858\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26858\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Ocean Island Volcanoes (OIVs) and seamounts are one of the most common, prominent and rapidly formed but least studied (from a geological\/volcanological point of view) features on Earth. OIVs, which represent only the summit section of a much larger volcanic edifice rising up from the sea floor, are highly vulnerable to geological hazards such as volcanism, seismic activity, mass wasting (caldera formation), landslides and rockfalls, and tsunamis. Specifically, a volcanic eruption on an OIV can mainly have a substantial impact on the local population, infrastructure and economy. It is then essential understand the characteristic behaviour and the ages of the recent eruptions of the volcano to enhance the capacity to identify future geological hazard processes such as eruptions, tsunamis, etc. In other words, to forecast how a volcano will behave, it is essential to identify, map and analyse the deposits from past eruptions and determine the ages of those deposits. However, this becomes more challenging on Ocean Island Volcanoes that have not experienced recent eruptions, such as Easter Island (Chile), but which may still pose a significant risk of future eruption.\r\nThis proposal focuses on Easter Island (Rapa Nui or Isla de Pascua), an isolated southeast Pacific island with 7.750 inhabitants, that receives more than 100.000 tourists per year. This island has been catalogued as one of the 92 active volcanos of Chile by the Chilean mining and geological service, occupying the 46th position in its Volcanic Risk ranking. It was included taking into account the recent activity focused on Terevaka volcano and its peripheral vents and other factors as the population and infrastructures exposure and its high amount of visitors per year. Nevertheless, there is still a lack of robust geochronology and volcano-stratigraphy and morphometry for Easter Island, especially for these most recent eruptions. Therefore, a comprehensive study of its Holocene eruptions regarding their styles, a more accurate age determination, and a well identification of submarine volcanic centres around the island is still pending to evaluate its potential volcanic hazard.\r\nThe main aim of this project is to identify and study the most recent eruptions of Easter Island, both onshore and offshore. This will allow understanding how and when they took place in terms of volume, diverse morphometric parameters, styles and their ages which will verify if the island is still active. To identify and characterize the style of the most recent eruptions (Holocene- last 11.700 Kyr) on the island it is planned to conduct geomorphologic and morhometryc analyses of subaerial and submarine recent volcanic deposits with and integrated onshore\/offshore approach. Also, volcano-stratigraphy for the most recent cones and associated deposits onshore, with special attention to those hydrovolcanic eruptions will be analysed. To determine the number of Holocene eruptions on the island, 14C (for charcoal), 40Ar\/39Ar (for rocks) techniques will be used. Moreover, we will identify and date tephras of lacustrine sedimentary records of the Rano Raraku, Rano Kao lakes and the Rano Aroi peat bog related to recent eruptions.\r\nA likely future eruption on the island or near its coasts would have negative and serious consequences; therefore, it is essential to undertake this scientific research aimed at improving the knowledge of the processes and their potential impacts. Furthermore, this study will also contribute to understanding the overall evolution of an interoceanic volcanic island whose results can be compared with other more studied OIVs in the world. In addition, this project will support undergraduate and graduate students, for whom this study will comprise most of their dissertation research, being an extraordinary opportunity for them. Moreover, this study will foster ongoing international collaboration, providing a pipeline for future student and faculty exchange, and will promote outreach educational experiences for the community, as well as more specialized seminars.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11240035<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024 - Abril 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26998\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Tracing the links between the volatile composition and oxygen fugacity of magmas, their ore fertility, and crustal thickness: A regional scale investigation of the Miocene to Mio-Pliocene arc segment of the Andes of central Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26998\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26998\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The world's transition to using cleaner energy sources to address climate change has led to a sharp rise in the demand for base and precious metals. Consequently, discovering new ore deposits to meet this growing demand and prevent supply shortages has emerged as one of the greatest challenges of the 21st century.   Discovery of new magmatic-hydrothermal ore deposits can be improved based on a fundamental understanding of the geological processes that control the flux and focusing of ore-constituting elements in the Earth\u0092s crust, and by identifying the differences between the bulk-rock and mineral chemistry of ore-forming and ordinary\u0097barren\u0097granitoids. Large metal anomalies in the Earth\u0092s upper crust, such as porphyry copper-(molybdenum) deposits (PCDs), occur in intimate association with oxidized and water-rich arc magmatism in subduction zones. However, these deposits occur in restricted crustal domains and form in response to specific tectono-magmatic events, indicating that not all arc magmas have the same ore-forming potential. Understanding why only some magmas produced large PCDs while most other arc magmas remain barren is a fundamental scientific question and key to developing efficient exploration strategies. \r\nThe volatile element composition of arc magmas, including water, sulfur, and halogens such as chlorine and fluorine, as well as their oxygen fugacity, exert a critical control on their ore-forming potential (i.e., ore fertility). These components are not only key to the complexation and transport of ore metals during hydrothermal activity, but also influence the amount of ore metals transported by magmas and the efficiency to which they are transferred from magmas to exsolved fluids. Magmatic differentiation in lower crustal hot zones beneath thick crustal regions is expected to enhance the volatile element budget and oxygen fugacity of evolving magmas that are discharged to the upper crust. This occurs due to the accumulation of incompatible volatile elements during successive cycles of recharge by mafic magmas and crystallization, facilitated by the deeper and hotter conditions beneath thicker arc crusts. As such, an increasingly recognized hypothesis holds that ore-forming magmas display a particularly increased budget of volatile elements and higher oxygen fugacities when compared to barren arc magmas, and that this is largely influenced by the arc crust thickness. The proposed work will test this hypothesis by focusing on the Miocene to Mio-Pliocene magmatism and associated world-class PCD mineralization in the Andes of central Chile.\r\nFrom the Early Miocene to the Mio-Pliocene, the arc segment located between latitudes ~33\u009634.5\u00b0 S in the Andes of central Chile has seen a continued increase in crustal thickness and has evolved from being barren in the Early Miocene to producing some of the largest PCDs of the world in the Mio-Pliocene, such as El Teniente and Rio Blanco-Los Bronces. This geological scenario and the spatial and age distribution of the associated outcropping intrusive rocks offer a unique opportunity to investigate the temporal evolution of the volatile composition of magmas and its consequences for ore fertility. The goal of this proposal is to examine, adopting a regional scale perspective, the evolution in the volatile composition and oxygen fugacity of magmas produced in this arc segment and its relationship to magmatic ore fertility, as well as how this may have been influenced by changes in crustal thickness.\r\nTo achieve this, I will sample an extensive suite of granitoids that represent a continuum from Early Miocene to Mio-Pliocene magmas, including porphyry-forming intrusions. By combining zircon petrochronology, apatite, biotite, and amphibole mineral chemistry, in conjunction with the bulk-rock composition of intermediate to felsic intrusive rocks, I will be able to constrain relative changes in the hydration state, sulfur contents, halogen and oxygen fugacities, as well as in their associated crustal thickness during the evolution of the selected arc segment. This will be done by implementing a combination of cutting-edge analytical techniques, including synchrotron-based sulfur X-ray absorption near edge structure spectroscopy, electron probe microanalysis, (laser ablation) inductively coupled plasma mass spectrometry, and X-ray fluorescence spectrometry. I aim at (1) testing the differences in the volatile composition of barren and ore-forming intrusive rocks; (2) determining whether there is a gradual change in the volatile systematics of magmas during the evolution of the studied arc segment; and (3) analyzing the relationship between variations in crustal thickness and the volatile composition of associated magmas.\r\nThe results of this proposal will lead to a better understanding of the magmatic controls underpinning the formation of giant PCDs and will provide valuable insights into identifying the differences between the bulk-rock and mineral chemistry of ore-forming and barren granitoids as tools for vectoring mineralized regions.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1241146<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024 - Marzo 2028<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26999\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Magmatic and Metallogenic Evolution of the Maricunga\u0096El Indio Belt\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26999\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26999\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11241126<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024 - Marzo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27026\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Controls on flank instability at southern Andes volcanoes constrained by field, laboratory, and numerical evidence: Applications to San Jos\u00e9 and Chill\u00e1n volcanoes\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27026\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27026\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The recently awarded Fondecyt Iniciaci\u00f3n no. 11241126 (PI Jorge Romero) aims to determine the distribution and geometry of slope instability and its controlling factors (i.e., textural and compositional characteristics of rocks, their mass structure and discontinuities, and their mechanical rock properties) at the San Jos\u00e9 and Nevados de Chill\u00e1n Volcanic Complexes. Specific objectives involve encompassing the production of thematic maps to represent the factors contributing to instability (e.g., magmatic intrusions, hydrothermal alteration areas, observed landslides, etc.) and defining and characterizing lithotechnical units based on field observations. In addition, it should determine the mechanical rock properties of natural samples based on laboratory tests that represent different scenarios. \r\n\r\nLastly, these results should be incorporated into numerical models to represent unstable areas, failure planes, and conditions for failure.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> N\u00b011240684<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024 - Marzo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27054\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Characterization of the immune response in Atlantic salmon infected with Tenacibaculum dicentrarchi and its relationship in the coinfection with Piscirickettsia salmonis.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27054\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27054\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Tenacibaculosis is an emerging pathogen recently classified as high-risk disease. Since 2020 it is the second pathogen after Piscirickettsia salmonis producing higher mortalities in Atlantic salmon. Diverses species of Tenacibaculosis has been described in Chile, but Tenacibaculum dicentrarchi present the higher prevalence in culture centers. Before 2018, underreporting of Tenacibaculosis was possible due to the external signology is similar with Piscirickettsiosis. P. salmonis is the main pathogen in Chilean salmon farming, causing the principals mortalities because of diseases. In recent years, concerns related to Tenacibaculosis and Piscirickettsiosis coinfection have increased due to detrimental effects on the health status of fish in comparison to the single infection. Our proposal aim to characterize the immune response elicit by T. dicentrarchi in Atlantic salmon and describe how it is related to a coinfection by P. salmonis. First, we propose the description of the single infection of T. dicentrarchi due to the lack of information about the immune response it induces in Atlantic salmon. Then, we propose the characterization of the coinfection between T. dicentrarchi and P. salmonis and the possible weaker of the health status of the fish due to T. dicentrarchi may favors the development of the secondary infection. Therefore, we hypothesize that \u0093Tenacibaculum dicentrarchi chronic infection triggers a type 2 immunity (Th2\/M2) IL-4\/13\/ IL-10+ phenotype in head kidney and spleen of Atlantic salmon, increasing the secretion of anti-inflammatory cytokine IL-10, which favor and increase the severity of Piscirickettsia salmonis coinfection\u0094. The general objective of the proposal is to demonstrate that a chronic infection of Tenacibaculum dicentrarchi causes in Atlantic salmon a status of head kidney and spleen immunosuppression presented an IL 4\/13\/ IL-10+ phenotype and increasing the mortality provoked by Piscirickettsia salmonis coinfection. To demonstrate the hypothesis, three specific objectives are proposed. First specific objective is \u0093Characterize the immunological response of the single infection of T. dicentrarchi and coinfection with T. dicentrarchi and P. salmonis in Atlantic salmon under field conditions during outbreak seasons\u0094. For this specific objective, we designed the Trial 1: Field sampling in open-sea cages during a single infection of T. dicentrarchi in winter and a coinfection with T. dicentrarchi and P. salmonis in spring. The analysis of the immune response will be through gene expression by RT-PCR and proteins by ELISA and western blotting. Then, the second objective propose is \u0093Verify the type 2 immunity (Th2\/M2) IL-4\/13\/ IL-10+ phenotype elicit by a T. dicentrarchi infection in Atlantic salmon under controlled conditions of laboratory\u0094. To accomplish this goal we designed the Trial 2: A single infection challenge with T. dicentrarchi in Atlantic salmon in laboratory conditions in order to better characterize the immune response at a cellular level by flow cytometry and a molecular level by RNA-seq, RT-PCR and protein level. The final specific objective is \u0093Characterize at the immunological level the development and severity of P. salmonis infection in Atlantic salmon infected by T. dicentrarchi under controlled conditions of laboratory\u0094. To achieve this objective we designed the Trial 3: A coinfection with T. dicentrarchi and P. salmonis in Atlantic salmon in laboratory conditions with the respective single infection controls of each pathogen and posterior analysis by molecular and protein level. The expected results are: 1) The characterization of the immune response at functional level of the single infection of T. dicentrarchi and the coinfection of T. dicentrarchi and P. salmonis in Atlantic salmon in open-sea cages; 2) Verification that T. dicentrarchi triggers a type 2 immunity (Th2\/M2) with an increase in the secretion of cytokine IL-10 demonstrated through transcript, protein, and cellular analysis in laboratory conditions that will let us a better resolution of the immune response characterization in comparison with the field conditions; 3) Characterization of the development of a more harmful P. salmonis infection due to the weaker health status on Atlantic salmon produced by of T. dicentrarchi, which means a higher bacterial load of P. salmonis and mortality rate in coinfected fish with T. dicentrarchi and P. salmonis. The results obtained in this research will provide animal health information to improve the productive management of salmonids and contribute to the knowledge of the health status of Atlantic salmon in the context of the two main pathogens affecting Chilean aquaculture nowadays.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11240404<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27117\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Cosas que educan. Un estudio videogr\u00e1fico-fenomenol\u00f3gico de la materialidad en experiencias formativas de pr\u00e1ctica profesional docente\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27117\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27117\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto se propone explorar la materialidad de las experiencias formativas en el practicum a trav\u00e9s de un estudio emp\u00edrico-cualitativo basado en el uso de la videograf\u00eda de orientaci\u00f3n fenomenol\u00f3gica. El foco espec\u00edfico en la materialidad considera dos hip\u00f3tesis: 1) en la FID predomina una visi\u00f3n instrumental de las cosas como herramienta, recurso o medio pedag\u00f3gico o did\u00e1ctico que dificulta, cuando no impide, examinar el estatus de la materialidad en la co-constituci\u00f3n de la experiencia pr\u00e1ctica docente; 2) la noci\u00f3n tradicional de reflexi\u00f3n en el paradigma del profesional reflexivo se mantiene en un nivel intelectual-cognitivo que suele desatender la dimensi\u00f3n corporal, preverbal y est\u00e9tica de la misma.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> N\u00ba3240435<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27029\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            PRODUCCI\u00d3N DE AMON\u00cdACO VERDE MEDIANTE LA ELECTROREDUCCI\u00d3N DE NOX USANDO TiCu\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27029\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27029\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto tiene como objetivo estudiar la producci\u00f3n de amoniaco mediante la electroreducci\u00f3n de NOx usando electrodos TiCu. Para lograrlo, se emplear\u00e1 el proceso de aleado mec\u00e1nico y sinterizaci\u00f3n v\u00eda compactaci\u00f3n en caliente de los electrodos TiCu y se evaluar\u00e1 su capacidad electrocatal\u00edtica y estabilidad en la RRNOx. Se espera que la adici\u00f3n de Cu en los electrodos TiCu aumente la eficiencia faradaica, lo que permitir\u00e1 una mayor producci\u00f3n de amon\u00edaco con una menor cantidad de energ\u00eda consumida. Se llevar\u00e1n a cabo an\u00e1lisis estructurales, morfol\u00f3gicos y composicionales de los electrodos TiCu utilizando t\u00e9cnicas como microscop\u00eda electr\u00f3nica y difracci\u00f3n de rayos X. Adem\u00e1s, se realizar\u00e1n pruebas electroqu\u00edmicas para evaluar la capacidad de los electrodos de la RRNOx para la producci\u00f3n de amoniaco. Se espera que los resultados obtenidos en este proyecto contribuyan al desarrollo cient\u00edfico y tecnolog\u00edas m\u00e1s sostenibles y eficientes para la producci\u00f3n de amon\u00edaco, lo que permitir\u00eda una menor dependencia de los combustibles f\u00f3siles y una mayor protecci\u00f3n del medio ambiente.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26056\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fostering Climate Change Resilience: Unveiling the Interplay of Soil, Grassland, Trees, and Animals in Semi-arid Chile through a Comprehensive Holistic Framework\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26056\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26056\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto de investigaci\u00f3n que apunta al estudio de practicas sostenibles para el manejo de sistemas silvopastoril en el secano costero. El proyecto involucra el estudio de la materia org\u00e1nica del suelo, adem\u00e1s de una serie de variables que pueden impactar el manejo de los agroecosistemas[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26458\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fostering Climate Change Resilience: Unveiling the Interplay of Soil, Grassland, Trees, and Animals in Semi-arid Chile through a Comprehensive Holistic Framework\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26458\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26458\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto de investigaci\u00f3n que apunta al estudio de practicas sostenibles para el manejo de sistemas silvopastoril en el secano costero. El proyecto involucra el estudio de la materia org\u00e1nica del suelo, adem\u00e1s de una serie de variables que pueden impactar el manejo de los agroecosistemas[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024 - Noviembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Fundaci\u00f3n para la Innovaci\u00f3n Agraria - FIA<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26631\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            SaviaLab Regi\u00f3n de O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26631\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26631\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]SaviaLab es la combinaci\u00f3n de dos t\u00e9rminos: Savia (la energ\u00eda, elemento vivificador) y Laboratorio (lugar con los medios para realizar investigaciones, experimentos y trabajos cient\u00edficos y t\u00e9cnicos). \r\nSaviaLab es una iniciativa impulsada por la Fundaci\u00f3n para la Innovaci\u00f3n Agraria (FIA), que busca ser un agente activo en el desarrollo de las comunidades educativas locales, impulsando la innovaci\u00f3n temprana con un enfoque silvoagropecuario, para la construcci\u00f3n de una sociedad m\u00e1s anal\u00edtica y propositiva. Promoviendo formas de vivir que reconozcan y releven las heterogeneidades culturales, ambientales y sociales, favoreciendo pr\u00e1cticas colaborativas en el respeto de la sabidur\u00eda y valores tradicionales en un entorno en constante transformaci\u00f3n. \r\nBuscamos contribuir con las comunidades educativas locales, en el desarrollo y fortalecimiento de habilidades y competencias, que favorezcan y promuevan el bienestar y el desarrollo integral de sus miembros y sus entornos, a trav\u00e9s de procesos de innovaci\u00f3n temprana con un enfoque silvoagropecuario.\r\nSaviaLab se trabajar\u00e1 en grupos de estudiantes quienes desarrollar\u00e1n un proyecto de innovaci\u00f3n a lo largo de toda la experiencia formativa. El avance del proyecto se llevar\u00e1 a cabo a trav\u00e9s de la realizaci\u00f3n de actividades individuales y grupales, as\u00ed como en clases o salidas a terreno, todas apoyadas con material did\u00e1ctico en formato hojas de trabajo. Adem\u00e1s, cada docente podr\u00e1 adoptar la metodolog\u00eda a diversas asignaturas o talleres, seg\u00fan su especialidad, y as\u00ed propiciar el trabajo colaborativo entre docentes. \r\nEl modelo de innovaci\u00f3n propuesto por SaviaLab, comprende un proceso de 2 fases: La fase Formativa seguida de la fase Concurso, espacio en donde los equipos de docentes y estudiantes presentan los resultados de lo desarrollado en la fase Formativa.\r\nLa fase formativa, considera 6 etapas conducentes al desarrollo de una idea innovadora, las cuales se distribuyen en dos unidades. Cada una de estas etapas plantea desaf\u00edos diferentes que adquieren sentido al ser considerados como parte de un proceso mayor: la innovaci\u00f3n temprana. \r\nEn su versi\u00f3n 2024, se ejecutar\u00e1 en un formato h\u00edbrido, que considera actividades presenciales y actividades remotas tanto para la Fase Formativa como para la Fase Concurso.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024 - Marzo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26080\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            La funci\u00f3n del cine como dispositivo para promover experiencias interculturales y el fortalecimiento de la inclusi\u00f3n social entre estudiantes migrantes y chilenos\/as en escuelas p\u00fablicas de O\u0092Higgins y el Maule\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26080\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26080\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El prop\u00f3sito del proyecto consiste en conocer si el cine de \u00edndole intercultural funciona como un mecanismo educativo capaz de contrarrestar actitudes de racismo o discriminaci\u00f3n en escuelas p\u00fablicas de las regiones de O'Higgins y del Maule, espec\u00edficamente, en escuelas p\u00fablicas que ofrecen ense\u00f1anza b\u00e1sica y que tienen alta\r\nmatr\u00edcula con ni\u00f1os y ni\u00f1as migrantes[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FONDECYT REGULAR 1241502<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024 - Marzo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26133\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fetal Programming of cardiovascular accelerated dysfunction and aging by intrauterine hypoxia\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26133\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26133\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Non-communicable diseases (NCDs) are responsible for 74% of worldwide human deaths, with cardiovascular\r\ncauses in the first place (1). NCDs are determined by a combination of environmental, genetic and epigenetic\r\nfactors. In fact, adverse intrauterine conditions, such as reduced oxygen availability (hypoxia) and oxidative\r\nstress, can increase the risk of developing diseases during life, a phenomenon known as Fetal Programming\r\nor Developmental Origins of Health and Disease (DOHaD). Intrauterine hypoxia (IUH) affects most of the\r\npregnancies in high altitudes populations (> 2500m) (2-4) and 3-4% in lowlands, with uteroplacental and\r\ndevelopmental complications (4,5). We, and a couple of others, have recently shown that IUH determines\r\ncardiovascular oxidative stress during lifespan affecting endothelial function and vasodilator capacity, similar\r\nto what is seen with aging. The hypoxia-induced responses during development are responsible for\r\nfetal survival, but also determine mechanisms that program postnatal cardiovascular function\r\nthat may increase cardiovascular health risks and accelerate aging (6). This proposal aims to\r\ndetermine the mechanisms and trace the origins and outcomes of cardiovascular dysfunction resulting from\r\nintrauterine hypoxia and oxidative stress, and further identify the interrelated senescence mechanisms in\r\nthe heart and blood vessels. To assess the aforementioned, we will study the effects of IUH on cardiovascular\r\naging along lifespan, as important regulators of the function, structure and biomechanical properties of the\r\ncardiovascular system.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FONDECYT REGULAR 1241502<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024 - Marzo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26333\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fetal Programming of cardiovascular accelerated dysfunction and aging by intrauterine hypoxia\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26333\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26333\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Non-communicable diseases (NCDs) are responsible for 74% of worldwide human deaths, with cardiovascular\r\ncauses in the first place (1). NCDs are determined by a combination of environmental, genetic and epigenetic\r\nfactors. In fact, adverse intrauterine conditions, such as reduced oxygen availability (hypoxia) and oxidative\r\nstress, can increase the risk of developing diseases during life, a phenomenon known as Fetal Programming\r\nor Developmental Origins of Health and Disease (DOHaD). Intrauterine hypoxia (IUH) affects most of the\r\npregnancies in high altitudes populations (> 2500m) (2-4) and 3-4% in lowlands, with uteroplacental and\r\ndevelopmental complications (4,5). We, and a couple of others, have recently shown that IUH determines\r\ncardiovascular oxidative stress during lifespan affecting endothelial function and vasodilator capacity, similar\r\nto what is seen with aging. The hypoxia-induced responses during development are responsible for\r\nfetal survival, but also determine mechanisms that program postnatal cardiovascular function\r\nthat may increase cardiovascular health risks and accelerate aging (6). This proposal aims to\r\ndetermine the mechanisms and trace the origins and outcomes of cardiovascular dysfunction resulting from\r\nintrauterine hypoxia and oxidative stress, and further identify the interrelated senescence mechanisms in\r\nthe heart and blood vessels. To assess the aforementioned, we will study the effects of IUH on cardiovascular\r\naging along lifespan, as important regulators of the function, structure and biomechanical properties of the\r\ncardiovascular system.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26296\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Centro de Modelamiento Matem\u00e1tico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26296\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26296\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Basal FB210005[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26331\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Epigenomic programming in the early fetal blood-brain barrier by gestational hypoxia: consequences for the neuro-endothelial lifespan.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26331\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26331\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The quality of fetal and early post-natal environment influences lifelong health and predicts the risk for a range of non-communicable chronic diseases (NCDs). These observations form the basis of the \"Developmental Origins of Health and Disease\" (DOHaD hypothesis), which indicates that the intrauterine signals that compromise fetal growth also act to \"program\" tissue differentiation in a manner that predisposes later illnesses. Interestingly, the DOHaD hypothesis asserts that some aging-associated diseases that occur in adults are closely related to the development and conditions in the intrauterine environment. Thus, aging and aging-associated diseases can be viewed, at least in part, as the result of a developmental program activated early in embryogenesis and persists throughout the organism's lifespan. On the other hand, one of the main consequences of this programming is Fetal Growth Restriction (FGR) and which remains a leading\r\ncause of perinatal morbidity and mortality, affecting about 10% of pregnancies, but the incidence is reportedly sixfold greater in low-income countries depending on the region surveyed's nutrition and health access availability. FGR is clinically defined as a fetal weight below the 10th percentile of normal for gestational age, associated with some loss of fetal-placental blood flow diagnosed by ultrasound, and it is a condition in which the potential growth of the fetus is negatively influenced by environmental and maternal factor; the short-term consequences of FGR are low birth weight (LBW) and the corresponding phenotype, which is associated with increased perinatal morbidity and mortality. Besides, the long-term effects include\r\na 2 to 3-fold increase in the risk of developing cerebrovascular disease in adulthood. Indeed, many neurodevelopmental dysfunctions originated in the antenatal period, but few studies have focused on how growth restriction interferes with normal brain development of the blood-brain barrier (BBB) in the FGR neonate. The BBB is a cellular network formed by a monolayer of neuro-endothelial and mural cells. The BBB regulates the transport of molecules into and out of the central nervous system (CNS) (selective permeability and integrity of the BBB). In cerebrovascular aging, BBB breakdown and dysfunction lead to leakages of components into the central nervous system (CNS), contributing to neurological deficits; growing evidence from genomic data shows that FGR vascular dysfunction is mediated by aging, with a series of prominent\r\nhallmarks, including genetic and epigenetic alterations. These aging-associated epigenetic changes include DNA methylation, histone modification, chromatin remodeling, and non-coding RNA (ncRNA) regulation; however, how this mechanism regulates the aging process and contributes to aging-related BBB dysfunction remains elusive. We hypothesize that the impaired fetal growth conditions associated with epigenetic programming of aging-related DNA methylation, chromatin remodeling, and miRNA-omic profile of complex junctional genes in the neuro-endothelium, which can alter BBB integrity and permeability, increasing cerebral damage which impacts the perinatal and adulthood neurocognitive function.\r\nThis hypothesis will be addressed by the study of the effects of gestational chronic hypoxia on the aging epigenetic programming of gene expression of junctional complexes: Tight junction, adherens junction, and Gap junction family\u0092s molecules, as important regulators of the permeability para and transcellular of the BBB. For this, we will use a well-established Guinea pig model of cerebrovascular programming (DOHaD model) to demonstrate DNA methylation shift, chromatin remodeling, miRNA-omic profile, and transcriptomic analyses in neuro-endothelial cells isolated from cortex and hippocampus from animals gestated under hypobaric hypoxia at two stages of life (juvenile period and adulthood). The methodology for this project is an in vivo assess locomotor, exploratory activity, and memory acquisition evaluation, and in vitro determinations of epigenetic regulation of aging in BBB from the cortex, hypothalamus, and neuro- endothelial cell culture primary at different stages of life in animals gestated under hypoxia. Our expected outcome is to improve the knowledge about neuro-endothelial epigenetic programming by aging induced by the FGR and enhance the characterization of those epigenomic patterns and mechanisms associated with BBB breakdown by intrauterine hypoxia. This project aims to demonstrate that the effect of gestational hypoxia can accelerate the permeability of the BBB by epigenetic mechanisms not yet studied and that these changes continue throughout life, producing further deterioration of brain function[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024 - Febrero 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>AGCID\/ Ministerio de relaciones exteriores<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26376\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26376\" aria-expanded=\"false\" aria-controls=\"collapse-26376\">\n                                            Intercambio de tecnolog\u00eda para el control de vectores y nem\u00e1todos gastrointestinales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26376\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26376\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La propuesta de trabajo se enfoca en abordar dos problem\u00e1ticas\r\ncruciales que afectan a Chile y M\u00e9xico: la parasitosis en ovinos y la\r\nenfermedad de Chagas. El objetivo es desarrollar estrategias conjuntas\r\npara hacer frente a estos desaf\u00edos.\r\n\r\nEn el \u00e1mbito de la parasitosis en ovinos, se observa que esta\r\nproblem\u00e1tica afecta tanto a la producci\u00f3n ovina como a la salud de los\r\nrumiantes en M\u00e9xico, generando p\u00e9rdidas econ\u00f3micas importantes.\r\nAdem\u00e1s, la resistencia antihelm\u00edntica en los par\u00e1sitos es un problema\r\nque requiere una soluci\u00f3n sostenible.\r\n\r\nPor otro lado, la enfermedad de Chagas est\u00e1 en aumento en ambos\r\npa\u00edses, representando una amenaza significativa para la salud p\u00fablica.\r\nLa falta de m\u00e9todos eficientes para controlar la infecci\u00f3n ha llevado\r\na la necesidad de medidas preventivas para evitar el contacto de las\r\nchinches\/vinchucas infectadas con humanos y mam\u00edferos dom\u00e9sticos.\r\n\r\nEn este contexto, se busca promover la colaboraci\u00f3n institucional\r\nentre M\u00e9xico y Chile para abordar estas problem\u00e1ticas de manera\r\nefectiva. Se propone desarrollar un producto nutrac\u00e9utico basado en el\r\nhongo comestible P. ostreatus para controlar los nematodos\r\ngastrointestinales en ovinos, con un enfoque en la econom\u00eda circular y\r\nla autosuficiencia agropecuaria.\r\n\r\nAdem\u00e1s, se planea implementar una metodolog\u00eda de uso de vol\u00e1tiles de\r\natracci\u00f3n de chinches\/vinchucas en poblaciones espec\u00edficas en M\u00e9xico y Chile,\r\ncon la colaboraci\u00f3n de instituciones gubernamentales. Esta estrategia\r\nno solo busca proteger a la poblaci\u00f3n en riesgo, sino tambi\u00e9n promover\r\nla igualdad de g\u00e9nero y atender las necesidades de las comunidades\r\nrurales y urbanas.\r\n\r\nEn resumen, este proyecto aborda desaf\u00edos significativos en la\r\nproducci\u00f3n ovina y la salud p\u00fablica en Chile y M\u00e9xico, promoviendo la\r\ncolaboraci\u00f3n entre ambos pa\u00edses y teniendo en cuenta la igualdad de\r\ng\u00e9nero y las necesidades de las comunidades afectadas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 112031001-PI2406<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26532\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Gesti\u00f3n del orden p\u00fablico y derecho a protesta \u00bfNociones contrapuestas en el Chile post-Estallido Social?\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26532\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26532\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La presente propuesta de investigaci\u00f3n busca identificar el impacto de las condiciones pol\u00edticas en que se\r\nllevan a cabo las protestas sobre el apoyo que la poblaci\u00f3n general pudiese brindar al uso de la fuerza por\r\nparte de Carabineros en la gesti\u00f3n del orden p\u00fablico durante la crisis de seguridad que enfrenta el pa\u00eds\r\ndesde marzo de 2022. As\u00ed, se espera explorar las condiciones (restricci\u00f3n\/facilitaci\u00f3n de manifestaciones\r\npor parte de las autoridades; cobertura period\u00edstica de manifestaciones; empleo de acciones violentas\r\npor parte de manifestantes; presencia de manifestantes y carabineros heridos; destrucci\u00f3n de\r\ninfraestructura p\u00fablica) que las personas podr\u00edan tomar en consideraci\u00f3n para (des) legitimar el empleo\r\nde la fuerza por parte de Carabineros en tiempos en que la confianza en la principal instituci\u00f3n a cargo\r\ndel orden p\u00fablico en Chile se ha restaurado paulatinamente luego de una actuaci\u00f3n marcada por el uso\r\ndesproporcionado de la fuerza durante el Estallido Social de 2019. Junto con lo anterior, vale la pena\r\nse\u00f1alar que, al momento de elaborar esta propuesta de investigaci\u00f3n, se discuten proyectos de ley\r\ntendientes a reforzar las atribuciones de Carabineros asociadas al uso de la fuerza para hacer frente tanto\r\na delitos de alta connotaci\u00f3n social como a ataques a efectivos policiales durante manifestaciones.\r\nTomando en cuenta lo descrito m\u00e1s arriba, esta investigaci\u00f3n espera adem\u00e1s ayudar a clarificar los\r\nmecanismos psicol\u00f3gicos y pol\u00edticos que permitir\u00edan a las personas lidiar entre la adhesi\u00f3n (o acuerdo)\r\ncon el derecho a protesta que debe ser resguardado y promovido por las autoridades en un r\u00e9gimen\r\ndemocr\u00e1tico, con la (aparente) necesidad de que Carabineros pueda realizar un mayor uso discrecional\r\nde la fuerza para asegurar la gesti\u00f3n del orden y seguridad p\u00fablica.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024 - Diciembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>National Science Foundation (USA)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26535\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            The Global Social Media Study\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26535\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26535\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Almost 5 billion people use social media worldwide. While much of research on social media has been conducted in the US and UK, emerging evidence suggests that social media might have very different effects on countries outside the US (Asimovic et. al, 2021; Ghai et. al, 2023; Lorenz-Spreen et. al, 2022). With social media\u0092s massive global usage, it is crucial to examine the causal effects of social media on important psychological outcomes, such as polarization and well-being.\r\n\r\nWe plan to conduct a global field experiment across multiple countries to test the causal effect of social media on polarization, intergroup attitudes and well-being around the world. Similar to prior \u0093global studies\u0094 conducted with the Social Identity and Morality Lab, such as the International Collaboration on Social and Moral Psychology: Covid-19 and the International Collaboration to Understand Climate Action, we aim to collaborate with a large team of researchers from countries around the globe to conduct a cross-cultural field experiment.\r\n\r\nIn this global field experiment, participants will be incentivized to temporarily reduce their social media screen-time for ~2 weeks. We will then examine how reducing social media usage affects polarization, intergroup attitudes, well-being, and a number of related outcomes (e.g., trust, political participation, belief in misinformation, etc.). The methods of the study will be modeled after prior social media deactivation studies (e.g, Asimovic et. al, 2021; Alcott et. al, 2020). We will also examine whether the effects of social media cessation are moderated by a number of country-level variables (such as the strength of a country\u0092s democracy, etc.) and individual difference variables. This global study will help inform a number of debates about the effect of social media in different cultural and political contexts.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 112031001-PI2406<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26718\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Gesti\u00f3n del orden p\u00fablico y derecho a protesta \u00bfNociones contrapuestas en el Chile post-Estallido Social?\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26718\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26718\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La presente propuesta de investigaci\u00f3n busca identificar el impacto de las condiciones pol\u00edticas en que se\r\nllevan a cabo las protestas sobre el apoyo que la poblaci\u00f3n general pudiese brindar al uso de la fuerza por\r\nparte de Carabineros en la gesti\u00f3n del orden p\u00fablico durante la crisis de seguridad que enfrenta el pa\u00eds\r\ndesde marzo de 2022. As\u00ed, se espera explorar las condiciones (restricci\u00f3n\/facilitaci\u00f3n de manifestaciones\r\npor parte de las autoridades; cobertura period\u00edstica de manifestaciones; empleo de acciones violentas\r\npor parte de manifestantes; presencia de manifestantes y carabineros heridos; destrucci\u00f3n de\r\ninfraestructura p\u00fablica) que las personas podr\u00edan tomar en consideraci\u00f3n para (des) legitimar el empleo\r\nde la fuerza por parte de Carabineros en tiempos en que la confianza en la principal instituci\u00f3n a cargo\r\ndel orden p\u00fablico en Chile se ha restaurado paulatinamente luego de una actuaci\u00f3n marcada por el uso\r\ndesproporcionado de la fuerza durante el Estallido Social de 2019. Junto con lo anterior, vale la pena\r\nse\u00f1alar que, al momento de elaborar esta propuesta de investigaci\u00f3n, se discuten proyectos de ley\r\ntendientes a reforzar las atribuciones de Carabineros asociadas al uso de la fuerza para hacer frente tanto\r\na delitos de alta connotaci\u00f3n social como a ataques a efectivos policiales durante manifestaciones.\r\nTomando en cuenta lo descrito m\u00e1s arriba, esta investigaci\u00f3n espera adem\u00e1s ayudar a clarificar los\r\nmecanismos psicol\u00f3gicos y pol\u00edticos que permitir\u00edan a las personas lidiar entre la adhesi\u00f3n (o acuerdo)\r\ncon el derecho a protesta que debe ser resguardado y promovido por las autoridades en un r\u00e9gimen\r\ndemocr\u00e1tico, con la (aparente) necesidad de que Carabineros pueda realizar un mayor uso discrecional\r\nde la fuerza para asegurar la gesti\u00f3n del orden y seguridad p\u00fablica.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 112031001-PI2406<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26911\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Gesti\u00f3n del orden p\u00fablico y derecho a protesta \u00bfNociones contrapuestas en el Chile post-Estallido Social?\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26911\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26911\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La presente propuesta de investigaci\u00f3n busca identificar el impacto de las condiciones pol\u00edticas en que se\r\nllevan a cabo las protestas sobre el apoyo que la poblaci\u00f3n general pudiese brindar al uso de la fuerza por\r\nparte de Carabineros en la gesti\u00f3n del orden p\u00fablico durante la crisis de seguridad que enfrenta el pa\u00eds\r\ndesde marzo de 2022. As\u00ed, se espera explorar las condiciones (restricci\u00f3n\/facilitaci\u00f3n de manifestaciones\r\npor parte de las autoridades; cobertura period\u00edstica de manifestaciones; empleo de acciones violentas\r\npor parte de manifestantes; presencia de manifestantes y carabineros heridos; destrucci\u00f3n de\r\ninfraestructura p\u00fablica) que las personas podr\u00edan tomar en consideraci\u00f3n para (des) legitimar el empleo\r\nde la fuerza por parte de Carabineros en tiempos en que la confianza en la principal instituci\u00f3n a cargo\r\ndel orden p\u00fablico en Chile se ha restaurado paulatinamente luego de una actuaci\u00f3n marcada por el uso\r\ndesproporcionado de la fuerza durante el Estallido Social de 2019. Junto con lo anterior, vale la pena\r\nse\u00f1alar que, al momento de elaborar esta propuesta de investigaci\u00f3n, se discuten proyectos de ley\r\ntendientes a reforzar las atribuciones de Carabineros asociadas al uso de la fuerza para hacer frente tanto\r\na delitos de alta connotaci\u00f3n social como a ataques a efectivos policiales durante manifestaciones.\r\nTomando en cuenta lo descrito m\u00e1s arriba, esta investigaci\u00f3n espera adem\u00e1s ayudar a clarificar los\r\nmecanismos psicol\u00f3gicos y pol\u00edticos que permitir\u00edan a las personas lidiar entre la adhesi\u00f3n (o acuerdo)\r\ncon el derecho a protesta que debe ser resguardado y promovido por las autoridades en un r\u00e9gimen\r\ndemocr\u00e1tico, con la (aparente) necesidad de que Carabineros pueda realizar un mayor uso discrecional\r\nde la fuerza para asegurar la gesti\u00f3n del orden y seguridad p\u00fablica.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11240615<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024 - Marzo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26912\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fondecyt Iniciaci\u00f3n: El rol de la Formaci\u00f3n Ciudadana en la Formaci\u00f3n Inicial Docente: Creencias, aproximaciones y estrategias\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26912\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26912\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El Objetivo General de este proyecto es \u0093Analizar c\u00f3mo se despliega la Formaci\u00f3n Ciudadana en la Formaci\u00f3n Inicial Docente en las universidades chilenas, dando cuenta de la pol\u00edtica institucional, el dise\u00f1o curricular y las creencias de acad\u00e9micos y futuros profesores\u0094. Sus Objetivos Espec\u00edficos son: 1) Describir la forma en c\u00f3mo se desarrolla la Formaci\u00f3n Ciudadana en las universidades chilenas, buscando analizar la pol\u00edtica institucional desplegada en estos espacios. 2) Analizar la incorporaci\u00f3n de la Formaci\u00f3n Ciudadana en los objetivos institucionales y el dise\u00f1o curricular en carreras de educaci\u00f3n en las universidades chilenas. 3. Examinar las creencias de acad\u00e9micos y futuros docentes de educaci\u00f3n sobre la Formaci\u00f3n Ciudadana, reflexionando sobre c\u00f3mo estas creencias impactan en la Formaci\u00f3n Inicial Docente.\r\nFundamentaci\u00f3n: En el contexto de una importante crisis de legitimidad del sistema pol\u00edtico, la pol\u00edtica educativa en Chile ha incorporado la Formaci\u00f3n Ciudadana, como un t\u00f3pico relevante. Recienmente, entre los hitos de la formaci\u00f3n ciudadana cabe destacar la promulgaci\u00f3n de la Ley 20.911 que \u0093Crea el Plan de Formaci\u00f3n Ciudadana (PFC) para los establecimientos educacionales reconocidos por el estado\u0094. Seg\u00fan la evidencia disponible, la implementaci\u00f3n de esta y otras normativas ha sido, hasta la fecha, limitada. As\u00ed, diversas investigaciones han mostrado que las pol\u00edticas de Formaci\u00f3n Ciudadana siguen dependiendo, en general, m\u00e1s de la iniciativa docente que de pol\u00edticas de los establecimientos (Zu\u00f1iga et al., 2020; Ojeda et al., 2021). Asimismo, se ha mostrado que los docentes desarrollan el proceso de ense\u00f1anza y aprendizaje sobre la ciudadan\u00eda de forma m\u00e1s bien intuitiva, amparados principalmente en sus creencias particulares\r\n(Jara Ibarra et al., 2022; Cox et al., 2022) y que las acciones pedag\u00f3gicas se desarrollan siguiendo\r\npatrones m\u00e1s bien tradicionales (Bonhomme et al., 2016). Toda esta evidencia destaca la necesidad de investigar sobre la Formaci\u00f3n Ciudadana en general, y sobre los procesos de Formaci\u00f3n Inicial Docente en particular ya que una formaci\u00f3n inicial docente robusta e innovadora permitir\u00eda incorporar la Formaci\u00f3n Ciudadana como un componente central de la escuela. Aunque existe una creciente literatura que ha analizado los procesos de Formaci\u00f3n Ciudadana en la Formaci\u00f3n Inicial Docente (Lobat\u00f3n et al., 2020; Garrido y Jim\u00e9nez, 2020; Carvajal-Meza et al., 2022; Defensor\u00eda de la Ni\u00f1ez, 2022), la mayor\u00eda de estas investigaciones se han centrado en describir c\u00f3mo se desarrolla la Formaci\u00f3n Ciudadana en casos de universidades espec\u00edficas, o, por el contrario, analizan el proceso de formaci\u00f3n solamente desde las creencias docentes o desde el curr\u00edculum prescrito. Este proyecto busca complementar y profundizar esta evidencia, a partir de un estudio del sistema de Formaci\u00f3n Inicial Docente desde la perspectiva curricular,\r\njunto con an\u00e1lisis de las creencias docentes en un conjunto acotado y comparable de universidades. De esta manera, el estudio pretende dar cuenta de las similitudes y diferencias en la Formaci\u00f3n Inicial Docente sobre Formaci\u00f3n Ciudadana, aspecto central en un sistema universitario heterog\u00e9neo y masificado como el chileno (Salazar y Leihy, 2017), discutiendo asimismo tanto la forma en c\u00f3mo los futuros docentes visualizan la Formaci\u00f3n Ciudadana y c\u00f3mo esta es implementada y ense\u00f1ada en las instituciones de educaci\u00f3n superior. Metodolog\u00eda: El estudio se estructura a trav\u00e9s de un dise\u00f1o mixto secuencial(Creswell &amp; Plano, 2011). En estos dise\u00f1os, ambas fases de investigaci\u00f3n se encuentran articuladas, y los\r\nresultados de una fase permiten organizar las siguientes. En este estudio, se propone una organizaci\u00f3n estructurada en tres fases diferenciadas, pero en parte superpuestas. Fase 1. An\u00e1lisis global (10 meses) Asociados principalmente con los Objetivo 1 y 2 de la presente investigaci\u00f3n, se propone realizar un An\u00e1lisis de Contenido. El An\u00e1lisis de Contenido ser\u00e1 aplicado a fuentes documentales y a fuentes secundarias relacionadas a la Formaci\u00f3n Inicial Docente, incluyendo principalmente informaci\u00f3n p\u00fablica como p\u00e1ginas web, perfiles de ingreso y egreso, mallas curriculares y documentos estrat\u00e9gicos de las instituciones. El levantamiento de esta informaci\u00f3n se realizar\u00e1 en cerca de 15 universidades chilenas, incluyendo a todas las carreras de Pedagog\u00eda impartidas por estas casas de estudio. Fase 2. Estudio de caso (15 meses) Para el cumplimiento de parte del objetivo 2 y el objetivo 3 del estudio, se seleccionar\u00e1n cuatro casos de estudio. El an\u00e1lisis de casos (Yin, 1994) posibilita la comprensi\u00f3n de un fen\u00f3meno contextualizado, buscando dar cuenta de patrones, interacciones y realidades no necesariamente presentes en toda la realidad social. En esta investigaci\u00f3n, la selecci\u00f3n de los casos corresponder\u00e1 a una selecci\u00f3n de \u0093casos extremos\u0094 (Stake, 2015) es decir, a casos que presenten importantes diferencias respecto a la intensidad y forma en la que desarrollan la Formaci\u00f3n Ciudadana en las universidades y en las carreras de Pedagog\u00eda. En esta etapa de utilizar\u00e1n el an\u00e1lisis de contenido, entrevistas semi-estructuradas, grupos focales y la observaci\u00f3n no participante de clases y\/o actividades finales de curso. Fase 3. Integraci\u00f3n de resultados (6 meses). En la fase final de la investigaci\u00f3n, se realizar\u00e1 la integraci\u00f3n de todos los\r\nresultados de la investigaci\u00f3n para responder de manera cabal los objetivos propuestos. A su vez, se considera el generar un producto para las universidades a las que se les realizar\u00e1 un seguimiento durante el estudio considerando los resultados obtenidos y tambi\u00e9n recomendaciones, tanto desde lo expuesto en discursos de participantes, como desde la literatura internacional.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26945\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Exploring designing ROS release materials for biofilm control of L. monocytogenes: Understanding molecular and genetic bacterial mechanisms under food-processing environments conditions.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26945\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26945\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Listeria monocytogenes (Lm) is a foodborne pathogen that causes listeriosis, a severe invasive disease, with\r\nmortality rates as high as 30 %. This pathogen has caused several foodborne outbreaks and product recalls\r\nworldwide, with significant economic consequences for the food industry. Lm can resist many stresses used\r\nin food-processing environments (FPE) to control bacterial growth. Biofilm formation is another strategy that\r\nallows Lm to persist in FPE and contaminate foods. In natural environments, biofilms often consist of mixedspecies communities with dynamic interactions between different species. The structure and persistence of\r\nthese biofilms are determined by community compositions, cooperative development, genomic background,\r\nenvironment-responsive gene expression, and the material on which the biofilm forms, among others. The\r\ndesign of materials with anti-bacterial and anti-biofilm properties is an emerging strategy to control the\r\npresence of foodborne pathogens in the FPE. Smart surfaces with on-demand antimicrobial protection\r\nthrough \u0093physical\u0094 activation are ideal for this application. For instance, conductive polymers and\r\npiezocatalytic materials generate reactive oxygen species (ROS) by photothermal or mechanical stimulus,\r\nrespectively. To further advance in the design of effective ROS-releasing antibiofilm materials, it is essential\r\nto understand the microbial interactions occurring in biofilms and how molecular mechanisms are regulated\r\nby the pathogen under ROS-based stress conditions. In this study, we hypothesize that \u0093The efficacy of ROSreleasing antibiofilm materials can be modulated based on knowledge of the interactions between Lm isolates\r\nand other species on biofilms formed under FPE simulated conditions and by identifying specific molecular\r\nmechanisms regulated by Lm isolates that persist under these environmental conditions.\u0094 This research will\r\ntake an interdisciplinary approach, integrating knowledge from different fields (microbiology, molecular\r\nbiology, chemistry, and materials science) to better understand the mechanisms involved in Lm biofilm\r\nformation under FPE conditions and use this information to design efficient materials to control bacterial\r\ncontamination. Our main aim is \u0093to investigate the interplay between Lm and other bacteria in ROS-releasing\r\nantibiofilm materials under FPE conditions and identify the molecular mechanisms that Lm activates.\u0094 Specific\r\naim-1 To define the best condition for tailor-made ROS generation in conductive polymers and\r\npolymer\/ZnO composites able to control Lm mixed biofilms. We will design and assess the ROS\r\ngeneration capabilities of conductive polypyrrole (PPy) and piezocatalytic polymer\/ZnO materials. We\r\ncurrently have a collection of 300 Lm strains isolated from various sources. Approximately 50% of these\r\nstrains have had their whole genomes sequenced. The effect of ROS-releasing materials on cell adhesion and\r\nbiofilm formation will be tested for Lm strains in the presence of other bacterial species isolated from FPE\r\n(mixed biofilm) at 8\u00baC. We will identify the best technical conditions of the ROS-releasing material to control\r\nor reduce Lm biofilm formation. In addition, we will know if the Lm strains have different levels of tolerance\r\nto ROS under the conditions that we will test. Specific aim-2: To identify Lm genetic features associated\r\nwith tolerance on ROS-releasing materials. Additional Lm strains from our collection will be sequenced.\r\nWe will also have access to Lm strains isolated from listeriosis outbreaks with their genome sequences. We\r\nwill analyze the genomes of Lm strains exhibiting varying levels of biofilm tolerance on ROS-releasing\r\nmaterials under FPE conditions. We will evaluate the association between genomic elements (virulence genes,\r\nresistance determinants, and other genomic variations) and the tolerance levels of the ROS-releasing\r\nmaterials to identify new genomic elements associated with biofilm formation. Specific aim-3: To identify\r\nmolecular programs and ecological roles activated by Lm in response to ROS-releasing material\r\nunder FPE conditions One material with adjusted photothermal and mechanical ROS generation will be\r\nselected to evaluate the global transcriptional response of Lm isolates able to tolerate ROS-releasing\r\nmaterials. We will evaluate this response considering FPE conditions: low temperature and mixed biofilms.\r\nIn this way, we will identify if some Lm isolates activate specific molecular mechanisms that are associated\r\nwith the persistence\/or higher tolerance to ROS-releasing materials under FPE conditions. Expected\r\noutcomes: This research will contribute to advancing the antibiofilm material design, understanding Lm\r\ngenetic characteristics, and identifying molecular mechanisms activated under conditions used in food\r\nprocessing areas, thus promoting improved food safety and industry practices.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 13-2024-EFA<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024 - Marzo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad Metropolitana de Ciencias de la Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26976\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            CONOCIMIENTO MATEM\u00c1TICO PARA LA ENSE\u00d1ANZA DE N\u00daMEROS Y OPERACIONES EN LA ESCUELA ESPECIAL PARA ESTUDIANTES CIEGOS\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26976\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26976\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Seg\u00fan Tan y colaboradores (2020), la ense\u00f1anza de las matem\u00e1ticas en la Educaci\u00f3n Especial ha tendido hacia un car\u00e1cter\r\nreparador que ha restringido el acceso al conocimiento, relegando a sus estudiantes a bajas expectativas, es decir, \u0093formas\r\ndeshumanizadas del aprendizaje matem\u00e1tico\u0094 (p. 22). Un factor clave para la superaci\u00f3n de esta problem\u00e1tica es el\r\nconocimiento del profesor que ense\u00f1a matem\u00e1ticas, entendido como el conocimiento profesional necesario para realizar\r\nlas tareas recurrentes al ense\u00f1ar matem\u00e1ticas, el que se ha mostrado como cr\u00edtico para fomentar el aprendizaje de las\r\nmatem\u00e1ticas escolares (e.g. Bl\u00f6meke et al., 2022). No obstante, este hecho tiene una particularidad cuando se trata de la\r\nense\u00f1anza a estudiantes ciegos. Por ejemplo, algunos autores se\u00f1alan que el conocimiento de este colectivo de profesores\r\nes ense\u00f1ar a los estudiantes estrategias de c\u00e1lculo especializadas, i.e., signograf\u00eda matem\u00e1tica, el \u00e1baco japon\u00e9s Soroban\r\no la m\u00e1quina de escribir braille (Brawand y Johnson, 2016). Este foco en el c\u00e1lculo estar\u00eda superado por la\r\ncomplementariedad que debiese darse con el profesor de aula regular, sin embargo, en las escuelas especiales para\r\nestudiantes ciegos, las y los encargados son educadores especiales. En este sentido, existe muy poca literatura respecto a\r\ncu\u00e1les son las estrategias m\u00e1s adecuadas para ense\u00f1ar a estos estudiantes (Klingenberg et al., 2019) y particularmente,\r\nrespecto a los conocimientos de educadores que los acompa\u00f1an en estos procesos (Pi\u00f1eiro y Calle, en prensa).\r\nPor lo anterior, este proyecto tiene como meta contribuir al aprendizaje de las matem\u00e1ticas de estudiantes ciegos de\r\neducaci\u00f3n b\u00e1sica, de una escuela especial. Para ello, ponemos el foco la caracterizaci\u00f3n del conocimiento matem\u00e1tico\r\npara la ense\u00f1anza sobre n\u00fameros y operaciones en aulas de estudiantes ciegos. Las preguntas que gu\u00edan esta investigaci\u00f3n\r\nson: \u00bfqu\u00e9 conceptos y habilidades moviliza el profesor de educaci\u00f3n de personas ciegas cuando ense\u00f1a el sistema de\r\nnumeraci\u00f3n y las operaciones aritm\u00e9ticas?, \u00bfqu\u00e9 uso realizan los profesores del conocimiento matem\u00e1tico para la\r\nense\u00f1anza en sus pr\u00e1cticas?\r\nEstas preguntas se operativizan a trav\u00e9s de un objetivo general que persigue \u0093caracterizar el conocimiento matem\u00e1tico\r\npara la ense\u00f1anza que ponen en juego los profesores de educaci\u00f3n especial de estudiantes ciegos al ense\u00f1ar n\u00fameros\r\ny operaciones\u0094. Para su consecuci\u00f3n se ha dise\u00f1ado un estudio cualitativo-exploratorio que se centra en el conocimiento\r\nmatem\u00e1tico para la ense\u00f1anza y el uso que dan a este conocimiento. Se realizar\u00e1 un estudio cualitativo siguiendo un videobased\r\napproach (Widjaja et al., 2019). Adem\u00e1s, se realizar\u00e1n entrevistas pre-grabaci\u00f3n de la clase que indaguen, mediante\r\nlas categor\u00edas del MTSK, aspectos del dise\u00f1o de la clase. Adem\u00e1s, entrevistas posteriores a las clases para revisar, en\r\nconjunto, episodios espec\u00edficos de las clases que otorguen mayor claridad a las decisiones tomadas en el aula. La\r\nracionalidad de focalizar en este tipo de escuela, tiene relaci\u00f3n con que en la gran mayor\u00eda de escuelas especiales no existe\r\nla posibilidad de que profesores de educaci\u00f3n especial trabajen colaborativamente con profesores de asignatura. As\u00ed, las\r\ny los educadores especiales deben hacerse cargo de la ense\u00f1anza de las matem\u00e1ticas a estos ni\u00f1os y ni\u00f1as sin haber sido\r\nformados en ello (Pi\u00f1eiro y Calle, 2023).[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 20-2024-EFA<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024 - Marzo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad Metropolitana de Ciencias de la Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26977\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            DESARROLLO DE LA MIRADA PROFESIONAL SOBRE SENTIDO NUM\u00c9RICO DE EDUCADORES ESPECIALES EN ESCUELAS PARA ESTUDIANTES SORDOS\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26977\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26977\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Tan y coautores (2020) sostienen que la ense\u00f1anza de matem\u00e1ticas en educaci\u00f3n especial tiende a ser restaurativa, lo que limita las oportunidades de los estudiantes de adquirir conocimientos y reduce sus expectativas, es decir, \u0093formas deshumanizadas del aprendizaje matem\u00e1tico\u0094 (p. 22). Un factor clave para superar este problema es su Mirada Profesional, es decir, el conjunto de tres habilidades interrelacionadas: prestar atenci\u00f3n a las estrategias de los ni\u00f1os, interpretar la comprensi\u00f3n de los ni\u00f1os y decidir c\u00f3mo responder bas\u00e1ndose en la comprensi\u00f3n de los ni\u00f1os (Jacobs et al., 2010). Sin embargo, este hecho tiene sus peculiaridades a la hora de ense\u00f1ar a estudiantes sordos. Podemos se\u00f1alar que el curr\u00edculo de matem\u00e1ticas es creado por y para personas oyentes, sin tener en cuenta las caracter\u00edsticas de la comunidad sorda, cuyo aprendizaje es principalmente visual y est\u00e1 mediado por el dominio de la lengua de se\u00f1as por parte de profesores y estudiantes. En este sentido, la literatura ha mostrado que los estudiantes sordos tienen un rendimiento reducido cuando se enfrentan a tareas matem\u00e1ticas (i.e., Pagliaro, 2010) y, aunque la p\u00e9rdida auditiva no es una causa de bajo rendimiento per se, puede ser un factor de riesgo (Blatto et al., 2007).\r\nEste proyecto pretende contribuir al aprendizaje de las matem\u00e1ticas en la educaci\u00f3n b\u00e1sica de estudiantes sordos de una escuela especial con enfoque en educaci\u00f3n bilingu&#776;e. En este contexto, el estudio se enfoca en el desarrollo de la Mirada Profesional o Noticing (Jacobs et al., 2010) del educador especial cuando ense\u00f1a matem\u00e1ticas y que se encuentra mediada por el uso de la Lengua de Se\u00f1as Chilena (LSCh) y el manejo de los recursos l\u00e9xico-gramaticales que son de naturaleza visual. Las preguntas que gu\u00edan esta investigaci\u00f3n son: \u00bfc\u00f3mo un curso de desarrollo profesional sobre sentido num\u00e9rico fomenta la Mirada Profesional en docentes de educaci\u00f3n especial para estudiantes sordos?, \u00bfqu\u00e9 rol juegan en el desarrollo de la Mirada Profesional el uso de la lengua de se\u00f1as y el uso de recursos semi\u00f3ticos multimodales para contribuir a la construcci\u00f3n de significaci\u00f3n del estudiante sordo?, \u00bfc\u00f3mo se representa la Mirada Profesional a trav\u00e9s del manejo del espacio se\u00f1ante y del manejo de la iconicidad para la representaci\u00f3n de significados?\r\nDe manera general, este proyecto se enmarca en las Investigaciones de Dise\u00f1o, considerada un paradigma metodol\u00f3gico emergente que estudia el aprendizaje de los estudiantes en contexto, y es usado principalmente para la exploraci\u00f3n de mejoras educacionales, as\u00ed como para describir nuevas formas de aprendizaje para los estudiantes (Cobb et al., 2007). Particularmente, esta investigaci\u00f3n se llevar\u00e1 a cabo a trav\u00e9s de dos fases: a) primero se realizar\u00e1 un experimento de ense\u00f1anza, el cual estudia la naturaleza del desarrollo de ideas, herramientas o modelos en los que est\u00e1n contenidos alumnos, profesores o grupos; en segundo lugar, realizaremos entrevistas individuales semiestructuradas, las que permitir\u00e1n profundizar con mayor detalle en las ideas de los profesores. En cuanto a los participantes, esta investigaci\u00f3n contar\u00e1 con la participaci\u00f3n de profesores de una escuela para estudiantes sordos (adjuntamos carta de compromiso). El foco de an\u00e1lisis de la informaci\u00f3n estar\u00e1 centrado en el curso de desarrollo profesional y en las producciones (escritas y orales) de los profesores, usando la t\u00e9cnica del an\u00e1lisis de contenido (Kuckartz, 2019).[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1241150<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024 - Diciembre 2028<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27039\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Predicting ecological and genomic vulnerability to Global Climate Change in an emblematic Western South American clade of lilies (Zephyranthes subg. Myostemma)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27039\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27039\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]This proposal ultimately seeks to provide information to guide conservation and management policies\r\nfor Myostemma species, and a model to assess the vulnerability to GCC in other organisms of the highly\r\nendemic and threatened CWRVF biodiversity hotspot. This project will generate the first complete genome\r\nsequence for Amaryllidoideae, which will have a global impact by enabling genome-based evolutionary,\r\nbreeding, biochemical, and pharmaceutical research.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI230159<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27040\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            ResilomicsNet: Establecimiento de una alianza internacional para potenciar la resiliencia clim\u00e1tica de especies de inter\u00e9s productivo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27040\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27040\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La\r\ncolaboraci\u00f3n entre nuestros grupos busca formar una alianza para fortalecer la\r\ninvestigaci\u00f3n cient\u00edfica y tecnol\u00f3gica y la formaci\u00f3n de capital humano calificado en\r\nGen\u00f3mica, Biolog\u00eda de Sistemas y Biotecnolog\u00eda, para mejorar la productividad de\r\nespecies agr\u00edcolas y acu\u00edcolas en un escenario de cambio clim\u00e1tico, vincul\u00e1ndonos con\r\nactores y necesidades del sector productivo. Con esta propuesta, buscamos crear un polo\r\nnacional de investigadores capacitados en las \u00faltimas herramientas y tecnolog\u00edas que siente\r\nla bases para la postulaci\u00f3n conjunta a proyectos asociativos y\/o de investigaci\u00f3n aplicada e\r\ninterdisciplinaria en el corto plazo, la producci\u00f3n de art\u00edculos cient\u00edficos y propiedad intelectual\r\ny la formaci\u00f3n de excelencia de las futuras generaciones.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27062\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Ra\u00edces Sostenibles: L\u00edderes Ambientales para la Acci\u00f3n Resiliente Local\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27062\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27062\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En el actual contexto de crisis planetaria y ante el notorio aumento de conflictos socioambientales, se reconoce la imperante\r\nnecesidad de fomentar una participaci\u00f3n activa por parte de las comunidades locales. El fundamento de nuestro modelo\r\nformativo no solo propicia la participaci\u00f3n de l\u00edderes ambientales, sino que tambi\u00e9n aspira a que estos l\u00edderes se conviertan en\r\nformadores de futuros l\u00edderes ambientales. El perfil y habilidades de las y los l\u00edderes ambientales, ser\u00e1n esenciales para ejercer\r\nun liderazgo positivo que pueda tener efectos favorables para nuestro medio ambiente. La literatura indica que l\u00edderes\r\nambientales efectivos e influyentes no s\u00f3lo consideran la preservaci\u00f3n del medioambiente en sus decisiones, sino que van m\u00e1s\r\nall\u00e1 del cumplimiento de normativas ambientales, asumiendo un papel activo y transformador. L\u00edderes ambientales efectivos\r\nmovilizan a otros a trav\u00e9s de la comunicaci\u00f3n, de sus motivaciones y conocimientos que las personas com\u00fanmente buscan en\r\nl\u00edderes. Si bien, lo que hace influyente a un l\u00edder depender\u00e1, en parte, de los problemas a resolver, cuando se trata de\r\nproblemas ambientales, las personas buscan l\u00edderes justos, con la experiencia y conocimientos necesarios, y efectivos a la hora\r\nde gestionar y accionar estrategias de cuidado del medioambiente. Los proyectos ambientales liderados por l\u00edderes en que las\r\npersonas conf\u00edan tienden a ser mejor recibidos por las comunidades. De manera similar, la investigaci\u00f3n sugiere que l\u00edderes\r\nambientales capaces de comunicar desaf\u00edos y urgencias ambientales, al tiempo que transmiten estrategias de abordaje para\r\nestos problemas, son m\u00e1s efectivos toda vez que proporcionan un sentido de urgencia, pero tambi\u00e9n la esperanza necesaria\r\npara evitar que personas y comunidades se sientan impotentes. Finalmente, l\u00edderes ambientales competentes o por prestigio\r\ngeneralmente son vistos como expertos, ya sea por conocimiento y\/o experiencia, y gozan de una buena reputaci\u00f3n buena\r\nreputaci\u00f3n debido a su compromiso de larga data con temas sociales.\r\nPara lograr lo anterior, el enfoque te\u00f3rico de nuestra propuesta apunta a la integraci\u00f3n del Modelo de Aprendizaje Experiencial\r\nde Kolb (2009). Este modelo, fundamentado en la teor\u00eda del aprendizaje experiencial, aporta una perspectiva valiosa para la\r\nformaci\u00f3n de l\u00edderes ambientales comunitarios que busca ofrecer una experiencia formativa din\u00e1mica que no solo transfiera\r\nconocimientos te\u00f3ricos, sino que tambi\u00e9n cultive habilidades pr\u00e1cticas para la acci\u00f3n en contextos locales. Para esto, se\r\nemplear\u00e1n estrategias did\u00e1cticas de situaciones reales de conflictos para favorecer el inter\u00e9s de los l\u00edderes en el desarrollo de\r\nlas actividades. Estas estrategias principalmente ser\u00e1n an\u00e1lisis de casos, juegos de rol, aprendizaje basado en problemas, e\r\nindagaci\u00f3n cient\u00edfica. Con el fin de favorecer el aprendizaje de los l\u00edderes ambientales, se considerar\u00e1 la teor\u00eda de aprendizaje\r\nde adultos que aborda tres grandes principios: la necesidad de aprender, para la cual se ha realizado una encuesta previa a\r\nl\u00edderes ambientales de la regi\u00f3n; el principio aplicable en la pr\u00e1ctica, que se desarrollar\u00e1 en cada m\u00f3dulo de aprendizaje del\r\nprograma; y, finalmente, el principio de reflexionar desde la experiencia y conocimientos, facilitado en cada sesi\u00f3n con\r\nreflexiones metacognitivas mientras se comparten experiencias para buscar soluciones conjuntas.\r\nFinalmente, el objetivo es influir en las pol\u00edticas p\u00fablicas, vinculando la participaci\u00f3n de las comunidades a temas\r\nmedioambientales. Un manual formativo permitir\u00e1 la aplicaci\u00f3n del programa en Chile, fortaleciendo la participaci\u00f3n ciudadana\r\nen liderazgos ambientales. La participaci\u00f3n ciudadana, junto con l\u00edderes, puede extenderse a trav\u00e9s de una red colaborativa a\r\nniveles regionales y nacionales, contribuyendo a la evaluaci\u00f3n de pol\u00edticas y decisiones para futuros sostenibles.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1240667<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024 - Marzo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27091\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Descripci\u00f3n y progresi\u00f3n de los significados ideacionales representados en los libros escolares de ingl\u00e9s\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27091\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27091\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"].[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>CEDEUS<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27096\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Exploraci\u00f3n de la justicia espacial-urbana en Chile: Diagn\u00f3stico, proyecci\u00f3n y propuestas para escenarios situacionalmente \u00f3ptimos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27096\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27096\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo general del proyecto\r\nOG. Explorar la justicia espacial-urbana en Chile analizando desde una perspectiva multiescalar las din\u00e1micas pol\u00edticas, sociales, econ\u00f3micas y del entorno construido que dan forma, en contextos de triple crisis, a los procesos urbanos. Se busca proponer un marco te\u00f3rico-metodol\u00f3gico para diagnosticar niveles de justicia espacial-urbana con el prop\u00f3sito de contribuir a la discusi\u00f3n sobre la generaci\u00f3n de herramientas para la b\u00fasqueda de m\u00e1s justicia espacial-urbana en escenarios situacionalmente \u00f3ptimos.\r\nObjetivos espec\u00edficos del proyecto\r\nOE1. Definir conceptualmente la justicia espacial-urbana en el contexto chileno, identificando y priorizando sus dimensiones y componentes en contextos de triple crisis.\r\nOE2. Desarrollar y validar indicadores que capturen las dimensiones y componentes de la justicia espacial-urbana y su influencia en los procesos urbanos mediante el estudio de dos casos de territorios putativos y an\u00e1lisis comparativos de diferentes contextos urbanos espec\u00edficos en Chile, identificando sus fortalezas, limitaciones y posibles \u00e1reas de mejora.\r\nOE3. Proponer principios y est\u00e1ndares de justicia espacial-urbana basados en los resultados obtenidos de la evaluaci\u00f3n de indicadores y la retroalimentaci\u00f3n de diversos actores sociales, con el prop\u00f3sito de contribuir a la formulaci\u00f3n de pol\u00edticas p\u00fablicas y estrategias de intervenci\u00f3n que promuevan escenarios de justicia espacial situacionalmente \u00f3ptimos en el pa\u00eds.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024 - Marzo 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26563\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26563\" aria-expanded=\"false\" aria-controls=\"collapse-26563\">\n                                            Fondo de investigaci\u00f3n para estudiantes de pregrado, II convocatoria verano 2024. Cristian Acevedo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26563\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26563\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Aplicaci\u00f3n de t\u00e9cnicas variacionales y de Ecuaciones Diferenciales Parciales en grafos para problemas de agrupaci\u00f3n de datos y para segmentaci\u00f3n de im\u00e1genes[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Patrocinante<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024 - Marzo 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26566\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26566\" aria-expanded=\"false\" aria-controls=\"collapse-26566\">\n                                            Fondo de investigaci\u00f3n para estudiantes de pregrado, II convocatoria verano 2024. Camilo Aliste\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26566\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26566\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Estudio e implementaci\u00f3n de m\u00e9todos h\u00edbridos para la resoluci\u00f3n computacional de EDP aplicadas a Ciencia de Datos.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Patrocinante<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024 - Enero 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26099\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Identificaci\u00f3n de perfiles y trayectorias tempranas de aprendizaje de las matem\u00e1ticas mediante el uso de t\u00e9cnicas de inteligencia artificial\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26099\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26099\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La literatura muestra que diferencias en las habilidades matem\u00e1ticas tempranas son fuertes predictores de desempe\u00f1o matem\u00e1tico posterior e incluso afectan la selecci\u00f3n de carreras universitarias. Adem\u00e1s, aquellos ni\u00f1os que ingresan a la etapa escolar con habilidades matem\u00e1ticas deficientes, mantienen bajos desempe\u00f1os acad\u00e9micos durante toda su trayectoria escolar. De hecho, las condiciones iniciales de aprendizaje matem\u00e1tico determinan las trayectorias futuras de aprendizaje. En este contexto, un proyecto FONDEF (2019 - 2021) de la Universidad de O\u0092Higgins nos permiti\u00f3 desarrollar el Test de Pensamiento Matem\u00e1tico (TPM, ver https:\/\/jugarmate.org\/tpm\/) para evaluar aprendizajes matem\u00e1ticos en niveles de pre-k\u00ednder, k\u00ednder y 1ro b\u00e1sico. El TPM es un test basado en siete juegos digitales cuya aplicaci\u00f3n en grupos grandes de estudiantes es r\u00e1pida y sencilla por lo que permite recolectar una gran cantidad de datos de aprendizaje con poco esfuerzo. En congruencia con avances recientes en el desarrollo de habilidades matem\u00e1ticas tempranas, este instrumento logra capturar dos dimensiones del pensamiento matem\u00e1tico infantil que son el pensamiento num\u00e9rico y el razonamiento espacial. Estos desarrollos previos presentan una gran oportunidad para investigar las condiciones iniciales de los aprendizajes matem\u00e1ticos y las posibles trayectorias de aprendizajes posteriores. La hip\u00f3tesis que sustenta este proyecto es que existen perfiles de pensamiento matem\u00e1tico temprano que son capturados en los puntajes TPM y que las primeras trayectorias de aprendizaje se pueden modelar como un tr\u00e1nsito por estos perfiles. En este contexto, el presente proyecto propone la aplicaci\u00f3n de algoritmos de inteligencia artificial para el procesamiento y visualizaci\u00f3n de datos TPM para primero identificar distintos perfiles de pensamiento matem\u00e1tico temprano para luego encontrar patrones de tr\u00e1nsito entre \u00e9stos perfiles y as\u00ed identificar trayectorias iniciales de aprendizaje matem\u00e1tico. La metodolog\u00eda propone analizar conjuntos de datos TPM obtenidos en una muestra de m\u00e1s de 700 estudiantes de prekinder, kinder y 1ro b\u00e1sico aplicando m\u00e9todos de reducci\u00f3n de dimensionalidad (p.ej., an\u00e1lisis de componentes principales) y algoritmos de agrupamiento (p.ej., clustering). Los resultados de los algoritmos de agrupamiento se interpretan como perfiles de pensamiento matem\u00e1tico, mientras que an\u00e1lisis de evoluci\u00f3n de perfiles se interpretan como las trayectorias iniciales de aprendizaje de las matem\u00e1ticas tempranas. Se espera que los resultados de esta investigaci\u00f3n se utilicen para el dise\u00f1o de intervenciones remediales personalizadas que permitan potenciar el desarrollo de habilidades matem\u00e1ticas tempranas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26151\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estudio multiproxy para comprender el paleoambiente del antiguo Lago Tagua Tagua (34\u00baS)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26151\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26151\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Reconstrucci\u00f3n del clima del Pleistoceno mediante paleoadn[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26152\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Tras las Huellas del Clima y la Cultura: Serie Temporal Clim\u00e1tica e Historia Humana de la Regi\u00f3n de O\u0092Higgins a Trav\u00e9s de Anillos de \u00c1rboles\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26152\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26152\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La madera ha sido usada a lo largo de la historia para crear objetos, muebles, viviendas, medios de transporte, y obras de arte. Estas piezas arqueol\u00f3gicas son indicadores paleoambientales esenciales para estudiar el cambio clim\u00e1tico en regiones con poca informaci\u00f3n sobre la variabilidad clim\u00e1tica reciente. La dendrocronolog\u00eda tiene un rol clave para poder comprender eventos y procesos hist\u00f3rico de los bosques a trav\u00e9s de los registros presentes en los anillos de crecimiento de los \u00e1rboles, y son ampliamente usados en reconstrucciones clim\u00e1ticas. La siguiente propuesta busca datar y estudiar piezas de madera hist\u00f3ricas (estructuras patrimoniales) y prehist\u00f3ricas (pseudo f\u00f3siles de la laguna de Tagua Tagua) de la regi\u00f3n de O\u0092Higgins, utilizando una aproximaci\u00f3n interdisciplinaria entre dendrocronolog\u00eda, arqueolog\u00eda y paleoclimatolog\u00eda. Espec\u00edficamente se establecen cuatro objetivos espec\u00edficos: (i) identificar y seleccionar piezas hist\u00f3ricas de museos y\/o estructuras patrimoniales con potencial dendrocronol\u00f3gico, (ii) explorar el yacimiento arqueol\u00f3gico de la Laguna Tagua Tagua como sitio de inter\u00e9s para la dendroarqueolog\u00eda utilizando radiocarbono, (iii) Construir una cronolog\u00eda de ancho de anillos de extensi\u00f3n milenaria para la regi\u00f3n de O'Higgins, (iv) Explorar cambios en la variabilidad clim\u00e1tica de la regi\u00f3n de O\u0092Higgins del cuaternario tard\u00edo utilizando la cronolog\u00eda regional de anillos de crecimiento y datos paleoambientales de radiocarbono. El primero se enfocar\u00e1 en una revisi\u00f3n exhaustiva de bibliograf\u00eda y registros de colecciones en museos y arquitectura antigua con el fin de identificar, a partir de caracteres morfol\u00f3gicos y\/o anat\u00f3micos, piezas de madera nativa que presenten potencial para ser utilizadas en estudios dendrocronol\u00f3gicos. Estas piezas ser\u00e1n seleccionadas con base en su relevancia hist\u00f3rica y capacidad para proporcionar informaci\u00f3n clim\u00e1tica. El segundo objetivo est\u00e1 orientado al levantamiento de informaci\u00f3n y datos prehist\u00f3ricos de piezas de madera que se puedan encontrar en la laguna Tagua Tagua, que, por medio de dataci\u00f3n cruzada y radiocarbono, se establezca una fecha estimada de la antig\u00fcedad de las muestras. En el tercer objetivo se confeccionar\u00e1 una cronolog\u00eda regional de ancho de anillos a partir de series existentes y de nuevas piezas de madera colectadas en los objetivos anteriores. Se espera abarcar la mayor extensi\u00f3n temporal posible para luego, por medio de la t\u00e9cnica de dataci\u00f3n cruzada, poder concatenar las series obtenidas de piezas de madera hist\u00f3ricas y arqueol\u00f3gicas, y crear una serie temporal extensa de resoluci\u00f3n anual. Finalmente, mediante an\u00e1lisis de regresiones lineales simples y m\u00faltiples, se explorar\u00e1n diferentes reconstrucciones paleoclim\u00e1ticas de la regi\u00f3n de O\u0092Higgins, esperando abarcar al menos los \u00faltimos 1000 a\u00f1os. En conclusi\u00f3n, esta propuesta posee relevancia en dos \u00e1reas de gran inter\u00e9s para el desarrollo cient\u00edfico de la regi\u00f3n; en primer lugar, permitir\u00e1 elaborar una serie temporal clim\u00e1tica de la regi\u00f3n de O\u0092Higgins que abarque un extenso periodo hist\u00f3rico, lo que proporcionar\u00e1 una visi\u00f3n m\u00e1s amplia y detallada de las variaciones clim\u00e1ticas pasadas en la regi\u00f3n y su posible relaci\u00f3n con el cambio clim\u00e1tico actual; y en segundo lugar, ser\u00e1 un aporte relevante para una mejor caracterizaci\u00f3n del uso hist\u00f3rico de la manera y su relaci\u00f3n con las comunidades, a trav\u00e9s de una contextualizaci\u00f3n hist\u00f3rica m\u00e1s completa gracias a la recopilaci\u00f3n de informaci\u00f3n y elaboraci\u00f3n de cronolog\u00edas. Por lo tanto, los resultados aportar\u00e1n a la valorizaci\u00f3n del patrimonio cultural y la comprensi\u00f3n de los procesos clim\u00e1ticos de la regi\u00f3n de O'Higgins.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26490\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Tras las Huellas del Clima y la Cultura: Serie Temporal Clim\u00e1tica e Historia Humana de la Regi\u00f3n de O\u0092Higgins a Trav\u00e9s de Anillos de \u00c1rboles\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26490\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26490\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La madera ha sido usada a lo largo de la historia para crear objetos, muebles, viviendas, medios de transporte, y obras de arte. Estas piezas arqueol\u00f3gicas son indicadores paleoambientales esenciales para estudiar el cambio clim\u00e1tico en regiones con poca informaci\u00f3n sobre la variabilidad clim\u00e1tica reciente. La dendrocronolog\u00eda tiene un rol clave para poder comprender eventos y procesos hist\u00f3rico de los bosques a trav\u00e9s de los registros presentes en los anillos de crecimiento de los \u00e1rboles, y son ampliamente usados en reconstrucciones clim\u00e1ticas. La siguiente propuesta busca datar y estudiar piezas de madera hist\u00f3ricas (estructuras patrimoniales) y prehist\u00f3ricas (pseudo f\u00f3siles de la laguna de Tagua Tagua) de la regi\u00f3n de O\u0092Higgins, utilizando una aproximaci\u00f3n interdisciplinaria entre dendrocronolog\u00eda, arqueolog\u00eda y paleoclimatolog\u00eda. Espec\u00edficamente se establecen cuatro objetivos espec\u00edficos: (i) identificar y seleccionar piezas hist\u00f3ricas de museos y\/o estructuras patrimoniales con potencial dendrocronol\u00f3gico, (ii) explorar el yacimiento arqueol\u00f3gico de la Laguna Tagua Tagua como sitio de inter\u00e9s para la dendroarqueolog\u00eda utilizando radiocarbono, (iii) Construir una cronolog\u00eda de ancho de anillos de extensi\u00f3n milenaria para la regi\u00f3n de O'Higgins, (iv) Explorar cambios en la variabilidad clim\u00e1tica de la regi\u00f3n de O\u0092Higgins del cuaternario tard\u00edo utilizando la cronolog\u00eda regional de anillos de crecimiento y datos paleoambientales de radiocarbono. El primero se enfocar\u00e1 en una revisi\u00f3n exhaustiva de bibliograf\u00eda y registros de colecciones en museos y arquitectura antigua con el fin de identificar, a partir de caracteres morfol\u00f3gicos y\/o anat\u00f3micos, piezas de madera nativa que presenten potencial para ser utilizadas en estudios dendrocronol\u00f3gicos. Estas piezas ser\u00e1n seleccionadas con base en su relevancia hist\u00f3rica y capacidad para proporcionar informaci\u00f3n clim\u00e1tica. El segundo objetivo est\u00e1 orientado al levantamiento de informaci\u00f3n y datos prehist\u00f3ricos de piezas de madera que se puedan encontrar en la laguna Tagua Tagua, que, por medio de dataci\u00f3n cruzada y radiocarbono, se establezca una fecha estimada de la antig\u00fcedad de las muestras. En el tercer objetivo se confeccionar\u00e1 una cronolog\u00eda regional de ancho de anillos a partir de series existentes y de nuevas piezas de madera colectadas en los objetivos anteriores. Se espera abarcar la mayor extensi\u00f3n temporal posible para luego, por medio de la t\u00e9cnica de dataci\u00f3n cruzada, poder concatenar las series obtenidas de piezas de madera hist\u00f3ricas y arqueol\u00f3gicas, y crear una serie temporal extensa de resoluci\u00f3n anual. Finalmente, mediante an\u00e1lisis de regresiones lineales simples y m\u00faltiples, se explorar\u00e1n diferentes reconstrucciones paleoclim\u00e1ticas de la regi\u00f3n de O\u0092Higgins, esperando abarcar al menos los \u00faltimos 1000 a\u00f1os. En conclusi\u00f3n, esta propuesta posee relevancia en dos \u00e1reas de gran inter\u00e9s para el desarrollo cient\u00edfico de la regi\u00f3n; en primer lugar, permitir\u00e1 elaborar una serie temporal clim\u00e1tica de la regi\u00f3n de O\u0092Higgins que abarque un extenso periodo hist\u00f3rico, lo que proporcionar\u00e1 una visi\u00f3n m\u00e1s amplia y detallada de las variaciones clim\u00e1ticas pasadas en la regi\u00f3n y su posible relaci\u00f3n con el cambio clim\u00e1tico actual; y en segundo lugar, ser\u00e1 un aporte relevante para una mejor caracterizaci\u00f3n del uso hist\u00f3rico de la manera y su relaci\u00f3n con las comunidades, a trav\u00e9s de una contextualizaci\u00f3n hist\u00f3rica m\u00e1s completa gracias a la recopilaci\u00f3n de informaci\u00f3n y elaboraci\u00f3n de cronolog\u00edas. Por lo tanto, los resultados aportar\u00e1n a la valorizaci\u00f3n del patrimonio cultural y la comprensi\u00f3n de los procesos clim\u00e1ticos de la regi\u00f3n de O'Higgins.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FON2300107 - Proyecto financiado por el Fondo de Investigaci\u00f3n y Desarrollo en Educaci\u00f3n (FONIDE)<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26588\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26588\" aria-expanded=\"false\" aria-controls=\"collapse-26588\">\n                                            Diagn\u00f3stico de la convivencia escolar en la educaci\u00f3n p\u00fablica y el rol de los SLEP para apoyar su mejora en el contexto de postpandemia\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26588\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26588\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La convivencia escolar refiere al proceso de aprender a vivir juntos y ha sido identificada como una pieza clave de la educaci\u00f3n. A nivel nacional se cuenta con evidencia sobre la merma en la convivencia escolar durante la pandemia y hay datos que sugieren su grave deterioro tras la reapertura de los establecimientos, principalmente reflejado en situaciones de violencia escolar. Sin embargo, no se cuenta con un diagn\u00f3stico sistem\u00e1tico de las din\u00e1micas de convivencia escolar y sus desaf\u00edos en la postpandemia, ni tampoco con una caracterizaci\u00f3n de las respuestas institucionales a los desaf\u00edos de convivencia, por lo que este estudio busca contribuir a cubrir este vac\u00edo. La investigaci\u00f3n se focalizar\u00e1 en los establecimientos que son parte de los Servicios Locales de Educaci\u00f3n P\u00fablica en reciente funcionamiento (11 SLEP), a fin de generar insumos para el fortalecimiento del rol de los SLEP vigentes y los que est\u00e1n implementarse, en tanto instancia clave de liderazgo intermedio para apoyar a los establecimientos de manera pertinente a sus contextos y en articulaci\u00f3n con la pol\u00edtica nacional. As\u00ed, el estudio busca aportar a la consolidaci\u00f3n del Sistema Nacional de Educaci\u00f3n P\u00fablica en articulaci\u00f3n con la Pol\u00edtica Nacional de Convivencia Escolar. \r\n\r\nEl Objetivo General es identificar los desaf\u00edos y estrategias de convivencia escolar en establecimientos p\u00fablicos tras la pandemia y sus implicancias para el liderazgo intermedio, a fin de informar el desarrollo de propuestas para reforzar las estrategias de apoyo de los SLEP a sus establecimientos. \r\n\r\nPor su parte, los Objetivos Espec\u00edficos son los siguientes:\r\n1. Caracterizar las principales competencias y pr\u00e1cticas de liderazgo a nivel intermedio y escolar identificadas por la literatura para promover din\u00e1micas de convivencia escolar positivas.\r\n2. Generar un diagn\u00f3stico de la convivencia escolar en establecimientos de los SLEP en funcionamiento, para identificar los principales desaf\u00edos. \r\n3. Caracterizar las respuestas y necesidades de apoyo de los establecimientos p\u00fablicos ante los desaf\u00edos de convivencia escolar. \r\n4. Reconocer las competencias y pr\u00e1cticas que contribuyen al rol de los SLEP para promover din\u00e1micas de convivencia escolar positivas.\r\n\r\nSe utilizar\u00e1 un dise\u00f1o mixto anidado concurrente de modelo dominante (Creswell y Creswell, 2018) que combina m\u00e9todos cuantitativos y cualitativos, siendo estos \u00faltimos los predominantes: buscan atender a los Objetivos Espec\u00edficos 2, 3 y 4, mientras que el an\u00e1lisis cuantitativo profundizar\u00e1 en el OE 2 para robustecer el diagn\u00f3stico de las din\u00e1micas de convivencia. Los datos producidos por ambos m\u00e9todos, junto con la revisi\u00f3n de literatura orientada al OE 1, ser\u00e1n integrados en el an\u00e1lisis final para responder al Objetivo General. \r\n\r\nEl an\u00e1lisis se basar\u00e1 en: a) An\u00e1lisis descriptivos y an\u00e1lisis factorial multinivel de los datos sobre clima de convivencia escolar de los cuestionarios SIMCE a estudiantes, apoderados y docentes (a\u00f1os 2017, 2018, 2022, 2023); b) 11 grupos focales online con directores (en total, 55 participantes) de establecimientos con bajos niveles de clima de convivencia escolar que son parte de los SLEP en funcionamiento; c) Entrevista semi-estructurada online con un profesional de la Unidad de Apoyo T\u00e9cnico-Pedag\u00f3gico de cada SLEP (en total, 11 entrevistas); d) Revisi\u00f3n sistem\u00e1tica de literatura experta sobre estrategias para promover din\u00e1micas de convivencia escolar positivas. Se seguir\u00e1n las gu\u00edas \u00e9ticas del Comit\u00e9 de \u00c9tica de la Instituci\u00f3n Patrocinante en todas las etapas del estudio.\r\n\r\nEste estudio relevar\u00e1 las voces de actores clave a nivel escuela (directores) y a nivel intermedio (profesionales de SLEP) sobre un \u00e1mbito fundamental de los procesos educativos que se encuentra actualmente gravemente desafiado: la convivencia escolar tras la pandemia. Ello, junto con el an\u00e1lisis de bases de datos y la revisi\u00f3n sistem\u00e1tica de literatura, permitir\u00e1 ofrecer, adem\u00e1s del Informe Final, cinco productos concretos para apoyar la implementaci\u00f3n de la Ley 21.040 de Nueva Educaci\u00f3n P\u00fablica en alineaci\u00f3n con la Pol\u00edtica Nacional de Convivencia Escolar vigente: un documento de Reporte; un seminario; un art\u00edculo acad\u00e9mico; una columna de opini\u00f3n; y una postulaci\u00f3n a FONDECYT de Iniciaci\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024 - Enero 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26701\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Identificaci\u00f3n de perfiles y trayectorias tempranas de aprendizaje de las matem\u00e1ticas mediante el uso de t\u00e9cnicas de inteligencia artificial\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26701\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26701\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La literatura muestra que diferencias en las habilidades matem\u00e1ticas tempranas son fuertes predictores de desempe\u00f1o matem\u00e1tico posterior e incluso afectan la selecci\u00f3n de carreras universitarias. Adem\u00e1s, aquellos ni\u00f1os que ingresan a la etapa escolar con habilidades matem\u00e1ticas deficientes, mantienen bajos desempe\u00f1os acad\u00e9micos durante toda su trayectoria escolar. De hecho, las condiciones iniciales de aprendizaje matem\u00e1tico determinan las trayectorias futuras de aprendizaje. En este contexto, un proyecto FONDEF (2019 - 2021) de la Universidad de O\u0092Higgins nos permiti\u00f3 desarrollar el Test de Pensamiento Matem\u00e1tico (TPM, ver https:\/\/jugarmate.org\/tpm\/) para evaluar aprendizajes matem\u00e1ticos en niveles de pre-k\u00ednder, k\u00ednder y 1ro b\u00e1sico. El TPM es un test basado en siete juegos digitales cuya aplicaci\u00f3n en grupos grandes de estudiantes es r\u00e1pida y sencilla por lo que permite recolectar una gran cantidad de datos de aprendizaje con poco esfuerzo. En congruencia con avances recientes en el desarrollo de habilidades matem\u00e1ticas tempranas, este instrumento logra capturar dos dimensiones del pensamiento matem\u00e1tico infantil que son el pensamiento num\u00e9rico y el razonamiento espacial. Estos desarrollos previos presentan una gran oportunidad para investigar las condiciones iniciales de los aprendizajes matem\u00e1ticos y las posibles trayectorias de aprendizajes posteriores. La hip\u00f3tesis que sustenta este proyecto es que existen perfiles de pensamiento matem\u00e1tico temprano que son capturados en los puntajes TPM y que las primeras trayectorias de aprendizaje se pueden modelar como un tr\u00e1nsito por estos perfiles. En este contexto, el presente proyecto propone la aplicaci\u00f3n de algoritmos de inteligencia artificial para el procesamiento y visualizaci\u00f3n de datos TPM para primero identificar distintos perfiles de pensamiento matem\u00e1tico temprano para luego encontrar patrones de tr\u00e1nsito entre \u00e9stos perfiles y as\u00ed identificar trayectorias iniciales de aprendizaje matem\u00e1tico. La metodolog\u00eda propone analizar conjuntos de datos TPM obtenidos en una muestra de m\u00e1s de 700 estudiantes de prekinder, kinder y 1ro b\u00e1sico aplicando m\u00e9todos de reducci\u00f3n de dimensionalidad (p.ej., an\u00e1lisis de componentes principales) y algoritmos de agrupamiento (p.ej., clustering). Los resultados de los algoritmos de agrupamiento se interpretan como perfiles de pensamiento matem\u00e1tico, mientras que an\u00e1lisis de evoluci\u00f3n de perfiles se interpretan como las trayectorias iniciales de aprendizaje de las matem\u00e1ticas tempranas. Se espera que los resultados de esta investigaci\u00f3n se utilicen para el dise\u00f1o de intervenciones remediales personalizadas que permitan potenciar el desarrollo de habilidades matem\u00e1ticas tempranas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FON2300107 - Proyecto financiado por el Fondo de Investigaci\u00f3n y Desarrollo en Educaci\u00f3n (FONIDE)<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26914\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26914\" aria-expanded=\"false\" aria-controls=\"collapse-26914\">\n                                            Diagn\u00f3stico de la convivencia escolar en la educaci\u00f3n p\u00fablica y el rol de los SLEP para apoyar su mejora en el contexto de postpandemia\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26914\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26914\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La convivencia escolar refiere al proceso de aprender a vivir juntos y ha sido identificada como una pieza clave de la educaci\u00f3n. A nivel nacional se cuenta con evidencia sobre la merma en la convivencia escolar durante la pandemia y hay datos que sugieren su grave deterioro tras la reapertura de los establecimientos, principalmente reflejado en situaciones de violencia escolar. Sin embargo, no se cuenta con un diagn\u00f3stico sistem\u00e1tico de las din\u00e1micas de convivencia escolar y sus desaf\u00edos en la postpandemia, ni tampoco con una caracterizaci\u00f3n de las respuestas institucionales a los desaf\u00edos de convivencia, por lo que este estudio busca contribuir a cubrir este vac\u00edo. La investigaci\u00f3n se focalizar\u00e1 en los establecimientos que son parte de los Servicios Locales de Educaci\u00f3n P\u00fablica en reciente funcionamiento (11 SLEP), a fin de generar insumos para el fortalecimiento del rol de los SLEP vigentes y los que est\u00e1n implementarse, en tanto instancia clave de liderazgo intermedio para apoyar a los establecimientos de manera pertinente a sus contextos y en articulaci\u00f3n con la pol\u00edtica nacional. As\u00ed, el estudio busca aportar a la consolidaci\u00f3n del Sistema Nacional de Educaci\u00f3n P\u00fablica en articulaci\u00f3n con la Pol\u00edtica Nacional de Convivencia Escolar. \r\n\r\nEl Objetivo General es identificar los desaf\u00edos y estrategias de convivencia escolar en establecimientos p\u00fablicos tras la pandemia y sus implicancias para el liderazgo intermedio, a fin de informar el desarrollo de propuestas para reforzar las estrategias de apoyo de los SLEP a sus establecimientos. \r\n\r\nPor su parte, los Objetivos Espec\u00edficos son los siguientes:\r\n1. Caracterizar las principales competencias y pr\u00e1cticas de liderazgo a nivel intermedio y escolar identificadas por la literatura para promover din\u00e1micas de convivencia escolar positivas.\r\n2. Generar un diagn\u00f3stico de la convivencia escolar en establecimientos de los SLEP en funcionamiento, para identificar los principales desaf\u00edos. \r\n3. Caracterizar las respuestas y necesidades de apoyo de los establecimientos p\u00fablicos ante los desaf\u00edos de convivencia escolar. \r\n4. Reconocer las competencias y pr\u00e1cticas que contribuyen al rol de los SLEP para promover din\u00e1micas de convivencia escolar positivas.\r\n\r\nSe utilizar\u00e1 un dise\u00f1o mixto anidado concurrente de modelo dominante (Creswell y Creswell, 2018) que combina m\u00e9todos cuantitativos y cualitativos, siendo estos \u00faltimos los predominantes: buscan atender a los Objetivos Espec\u00edficos 2, 3 y 4, mientras que el an\u00e1lisis cuantitativo profundizar\u00e1 en el OE 2 para robustecer el diagn\u00f3stico de las din\u00e1micas de convivencia. Los datos producidos por ambos m\u00e9todos, junto con la revisi\u00f3n de literatura orientada al OE 1, ser\u00e1n integrados en el an\u00e1lisis final para responder al Objetivo General. \r\n\r\nEl an\u00e1lisis se basar\u00e1 en: a) An\u00e1lisis descriptivos y an\u00e1lisis factorial multinivel de los datos sobre clima de convivencia escolar de los cuestionarios SIMCE a estudiantes, apoderados y docentes (a\u00f1os 2017, 2018, 2022, 2023); b) 11 grupos focales online con directores (en total, 55 participantes) de establecimientos con bajos niveles de clima de convivencia escolar que son parte de los SLEP en funcionamiento; c) Entrevista semi-estructurada online con un profesional de la Unidad de Apoyo T\u00e9cnico-Pedag\u00f3gico de cada SLEP (en total, 11 entrevistas); d) Revisi\u00f3n sistem\u00e1tica de literatura experta sobre estrategias para promover din\u00e1micas de convivencia escolar positivas. Se seguir\u00e1n las gu\u00edas \u00e9ticas del Comit\u00e9 de \u00c9tica de la Instituci\u00f3n Patrocinante en todas las etapas del estudio.\r\n\r\nEste estudio relevar\u00e1 las voces de actores clave a nivel escuela (directores) y a nivel intermedio (profesionales de SLEP) sobre un \u00e1mbito fundamental de los procesos educativos que se encuentra actualmente gravemente desafiado: la convivencia escolar tras la pandemia. Ello, junto con el an\u00e1lisis de bases de datos y la revisi\u00f3n sistem\u00e1tica de literatura, permitir\u00e1 ofrecer, adem\u00e1s del Informe Final, cinco productos concretos para apoyar la implementaci\u00f3n de la Ley 21.040 de Nueva Educaci\u00f3n P\u00fablica en alineaci\u00f3n con la Pol\u00edtica Nacional de Convivencia Escolar vigente: un documento de Reporte; un seminario; un art\u00edculo acad\u00e9mico; una columna de opini\u00f3n; y una postulaci\u00f3n a FONDECYT de Iniciaci\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI230047<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25984\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Vinculaci\u00f3n internacional para la evaluaci\u00f3n de la capacidad centinela de moluscos bivalvos filtradores en el monitoreo de contaminantes emergentes en \u00e1reas costeras marinas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25984\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25984\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Vinculaci\u00f3n internacional para la evaluaci\u00f3n de la capacidad centinela de moluscos bivalvos filtradores en el monitoreo de contaminantes emergentes en \u00e1reas costeras marinas[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024 - Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26001\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            An\u00e1lisis multi\u00f3mico de redes reguladoras post-transcripcionales microARN- ARNm en el m\u00fasculo esquel\u00e9tico humano envejecido.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26001\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26001\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Durante las \u00faltimas d\u00e9cadas, la expectativa de vida promedio ha aumentado dram\u00e1ticamente, mientras\r\nque la salud no ha aumentado proporcionalmente. Para Chile se espera que para el 2050 el n\u00famero de\r\nadultos mayores superar\u00e1 el 30% de la poblaci\u00f3n con un incremento del 109% respecto al 2015,\r\nsuperando el 75% proyectado para la poblaci\u00f3n mundial. Entender el proceso de envejecimeinto y\r\nencontrar marcadores biol\u00f3gicos con capacidad diagn\u00f3stica y pron\u00f3stica, permitir\u00e1 promover estrategias\r\npara aumentar el n\u00famero de a\u00f1os de vida saludable, disminuyendo los gastos en salud asociado al\r\nenvejecimiento.\r\nVarios estudios han permitido avanzar y entender los mecanismos moleculares de p\u00e9rdidad de funci\u00f3n\r\nmuscular durante el evenjecimiento, m\u00e1s conocida como sarcopenia. Sin embargo, la complejidad del\r\nproceso y el insuficiente conocimiento de los mecanismos subjacentes dificultan el dise\u00f1o de estrategias\r\nterap\u00e9uticas eficaces. Hasta el momento, la actividad f\u00edsica y el ejercicio siguen siendo la estrategia m\u00e1s\r\neficaz para previnir y tratar la sarcopenia. Por lo cual, identificar nuevos biomarcadores musculares en\r\ncombinaci\u00f3n con marcadores cl\u00ednicos bien establecidos de par\u00e1metros f\u00edsicos y funcionales, fortalecer\u00eda\r\nla actual evaluaci\u00f3n geri\u00e1trica, al utilizar un enfoque interdiciplinario.\r\nLos microRNA (miRNA, 18\u009625 nt de largo) han ganado inter\u00e9s debido a que son mol\u00e9culas altamente\r\nconservadas en todas las especies, y act\u00faan como reguladores positivos y\/o negativos de la expresi\u00f3n\r\ng\u00e9nica. Entender la relaci\u00f3n reguladora directa entre los miARN y el ARN mensajero (mRNA) desempe\u00f1a\r\nen el m\u00fasculo esquel\u00e9tica es fundamentaltanto para el proceso de transcripci\u00f3n del ARNm y traducci\u00f3n\r\nde prote\u00ednas como para entender el deterioro de la funci\u00f3n muscular. Sin embargo, la regulaci\u00f3n de la\r\nred post-transcripcional miARN-ARNm y los mecanismos gen\u00e9ticos involucrados en el proceso de\r\nenvejecimiento del m\u00fasculo esquel\u00e9tico humano est\u00e1n lejos de ser elucidados.\r\nEn el presente estudio, nuestro objetivo es explorar e integrar coperfiles emparejados de miARN y ARNm\r\ndurante la p\u00e9rdida de funci\u00f3n muscular producidad durante el envejecimeinto en personas mayores. Este\r\nan\u00e1lisis integral permitir\u00e1 la identificaci\u00f3n de nuevos blancos de miARN y estrategias reguladoras que\r\ncontrolan la expresi\u00f3n g\u00e9nica en la p\u00e9rdidad de funci\u00f3n del m\u00fasculo esquel\u00e9tico y c\u00f3mo \u00e9stas son\r\nmodificadas por el entrenamiento de fuerza.\r\nSe hipotetiza que existen redes de regulaci\u00f3n post-transcripcional miRNA\/mRNA que se expresan de\r\nmanera diferencial en el m\u00fasculo esquel\u00e9tico de personas j\u00f3venes y personas mayores, que estar\u00edan\r\nasociadas con cambios en la funci\u00f3n muscular durante el envejecimiento. Adem\u00e1s, el entrenamiento de\r\nfuerza modifica estas redes de regulaci\u00f3n, lo que podr\u00eda contribuir a la mejora de la funci\u00f3n muscular y la\r\nprevenci\u00f3n o atenuaci\u00f3n de la sarcopenia.\r\nObjetivos generales\r\n- Identificar las redes de regulaci\u00f3n post-transcripcional miRNA\/mRNA involucradas en la\r\np\u00e9rdida de funci\u00f3n musclular en personas mayores que son moduladas por un entrenamiento\r\nde fuerza, para proponer nuevos biomarcadores de funci\u00f3n muscular durante el\r\nenvejecimeinto que se correlacionan con par\u00e1metros cl\u00ednicos\/funcionales.\r\nObjetivos espec\u00edficos\r\n1. Determinar las redes de regulaci\u00f3n post-transcripcional miRNA\/mRNA que se expresan\r\ndiferencialmente en el m\u00fasculo esquel\u00e9tico de personas j\u00f3venes y personas mayores.\r\n2. Identificar las redes de regulaci\u00f3n post-transcripcional miRNA\/mRNA que se modifican\r\ndespu\u00e9s de 12 semanas de entrenamiento de fuerza en personas mayores\r\n3. Correlacionar las redes miRNA\/mRNA identificadas con par\u00e1metros bioqu\u00edmicos, f\u00edsicos y\r\nfuncionales de funci\u00f3n muscular, antes y despu\u00e9s de 12 semanas de entrenamiento de\r\nfuerza en personas mayores\r\nEste proyecto busca Identificar nuevos biomarcadores de funci\u00f3n muscular durante el envejecimiento,\r\npodr\u00edan ser utilizados en futuros estudios y en la pr\u00e1ctica cl\u00ednica para evaluar la salud muscular en\r\npersonas mayores. Adem\u00e1s, de contribuir a una mejor comprensi\u00f3n de los mecanismos moleculares que\r\nsubyacen a la p\u00e9rdida de masa muscular en el envejecimiento y c\u00f3mo la intervenci\u00f3n del entrenamiento\r\nde fuerza puede modificar esos mecanismos. Finalmente, el uso de tecnolog\u00edas avanzadas de\r\nsecuenciaci\u00f3n (mARN y miARN) y bioinform\u00e1tica permitir\u00e1 impulsar el desarrollo y la mejora de t\u00e9cnicas\r\nde secuenciaci\u00f3n y an\u00e1lisis de datos en el campo de la gen\u00f3mica y la transcript\u00f3mica en el \u00e1rea del\r\nenvejecimiento, como tambi\u00e9n, promover la colaboraci\u00f3n a nivel nacional e internacional a trav\u00e9s de las\r\nbases de datos y recursos bioinform\u00e1ticos generados que estar\u00e1n a disposici\u00f3n de investigadores del \u00e1rea.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI230206<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26037\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Red acad\u00e9mica internacional y multidisciplinaria para el fortalecimiento de la investigaci\u00f3n, docencia y formaci\u00f3n de capital humano avanzado en el desarrollo de habilidades matem\u00e1ticas y pensamiento matem\u00e1tico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26037\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26037\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La formaci\u00f3n de ciudadanos y ciudadanas capaces de afrontar los desaf\u00edos sociales y tecnol\u00f3gicos actuales requiere de capacidades matem\u00e1ticas que van m\u00e1s all\u00e1 del foco tradicional en contenidos espec\u00edficos y que den paso, en cambio, al desarrollo de habilidades matem\u00e1ticas y de pensamiento matem\u00e1tico. La realidad educativa chilena evidencia que los logros acad\u00e9micos en matem\u00e1tica han estado estancados por varios a\u00f1os, para luego sufrir un retroceso durante el per\u00edodo de pandemia. Si bien, desde 2012, los lineamientos curriculares de la asignatura de Matem\u00e1tica incluyen expl\u00edcitamente un foco en pensamiento matem\u00e1tico y objetivos de aprendizaje ligados a cuatro habilidades, docentes de todos los niveles educativos tienden a carecer de herramientas y competencias para desarrollarlas. Los numerosos desaf\u00edos de la formaci\u00f3n docente de pregrado, posgrado y formaci\u00f3n continua se profundizan al considerar la realidad de regiones distintas a la Metropolitana.\r\n\r\nEn este contexto, se destaca la creaci\u00f3n en 2015 de la Universidad de O\u0092Higgins como una decisi\u00f3n para potenciar el acceso a la educaci\u00f3n superior de una regi\u00f3n hist\u00f3ricamente postergada. En la actualidad, la Universidad de O\u0092Higgins cuenta con una carrera de Pedagog\u00eda en Matem\u00e1tica, formaci\u00f3n especializada en matem\u00e1tica en su carrera de Pedagog\u00eda en Educaci\u00f3n B\u00e1sica, y con un proyecto de programa de Mag\u00edster en Ense\u00f1anza y Aprendizaje de la Matem\u00e1tica cuya implementaci\u00f3n se proyecta para 2024. Alrededor de estos programas, se ha generado un equipo de investigadores(as) y docentes proveniente de diversas disciplinas \u0096grupo de investigaci\u00f3n GeaMat\u0096 que comparten un inter\u00e9s com\u00fan por mejorar la educaci\u00f3n matem\u00e1tica a trav\u00e9s de empoderar a los y las docentes con herramientas y competencias para el desarrollo de habilidades matem\u00e1ticas y el pensamiento matem\u00e1tico en distintos niveles del sistema educativo.\r\n\r\nLa presente propuesta busca consolidar estos v\u00ednculos a trav\u00e9s de la articulaci\u00f3n de una Red acad\u00e9mica multidisciplinaria, nacional e internacional, que potencie la investigaci\u00f3n, la docencia y la formaci\u00f3n de capital humano avanzado en educaci\u00f3n matem\u00e1tica, con foco particular en el estudio y desarrollo de habilidades matem\u00e1ticas y el pensamiento matem\u00e1tico. El equipo chileno, liderado por la Universidad de O\u0092Higgins con participaci\u00f3n de la Universidad Cat\u00f3lica de la Sant\u00edsima Concepci\u00f3n y la Universidad Metropolitana de Ciencias de la Educaci\u00f3n, confluir\u00e1 con un equipo de investigadores(as) de Espa\u00f1a, Costa Rica y B\u00e9lgica. Los miembros del equipo nacional cuentan con un historial de vinculaci\u00f3n previa con los(as) investigadores(as) del extranjero, que se extiende en varios casos por m\u00e1s de cinco a\u00f1os y se continuar\u00e1 articulando a trav\u00e9s de esta propuesta buscando potenciar la realizaci\u00f3n de iniciativas de investigaci\u00f3n y desarrollo conjuntas, as\u00ed como fortalecer la formaci\u00f3n de pre y posgrado en el \u00e1rea en las instituciones nacionales. En particular, se espera como resultados de este proyecto: 1) la consolidaci\u00f3n del grupo de investigaci\u00f3n GeaMat, creado recientemente en la Universidad de O\u0092Higgins, 2) el desarrollo de dos proyectos de investigaci\u00f3n de forma colaborativa en la Red, 3) la realizaci\u00f3n de reuniones de intercambio de experiencias de formaci\u00f3n de pre y posgrado en educaci\u00f3n matem\u00e1tica, y 4) la elaboraci\u00f3n de un documento con recomendaciones para el desarrollo de habilidades y pensamiento matem\u00e1tico en diferentes contextos educativos. De esta forma, se espera que esta propuesta produzca impactos tanto en el \u00e1mbito cient\u00edfico como en el \u00e1mbito educativo regional y nacional.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 230157<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024 - Junio 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26045\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Reduciendo las desigualdades educativas a trav\u00e9s de la relaci\u00f3n entre familia y escuela\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26045\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26045\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetivo principal de este proyecto es analizar y comprender c\u00f3mo la interacci\u00f3n entre\r\nescuela y familia puede generar altas expectativas compartidas para reducir las brechas\r\neducativas. Esto considerando dos perspectivas, una local y aplicada y otra global y con foco\r\nen el desarrollo de conocimiento b\u00e1sico. Desde la perspectiva local, tenemos que Chile, y en\r\nparticular la Regi\u00f3n de O'Higgins, presenta desaf\u00edos complejos en t\u00e9rminos de desigualdades\r\neducativas asociadas a factores socioecon\u00f3micos y de ruralidad. Las brechas educativas son\r\nun problema persistente, asociado a un sistema educacional extremadamente segregado. Por\r\notra parte, desde una perspectiva global, las desigualdades educativas son un problema\r\nmunidal, con especificidades de cada contexto, y es necesario entender qu\u00e9 tipos de relaciones\r\nfamilia-escuela permiten reducir desigualdades. Adem\u00e1s, uno de los objetivos de desarrollo\r\nsostenible es alcanzar una educaci\u00f3n de calidad para todos y todas, y este proyecto apunta al\r\nlogro de ese objetivo[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 112031001-PI2404<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024 - Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26185\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Construcci\u00f3n in-silico de redes reguladoras miRNA:mRNA de especies vegetales end\u00e9micas del desierto de Atacama en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26185\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26185\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetivo principal de esta propuesta es estudiar las redes de regulaci\u00f3n post-transcripcionale de miARNs en especies vegetales del desierto de Atacama, su adaptaci\u00f3n a ambientes extremos e interacci\u00f3n con el medio donde habita. \r\n\r\nSe propone  un enfoque que integra (1) la implementaci\u00f3n de un nuevo m\u00e9todo computacional para predecir estas interacciones miARN:ARNm que permita integrar informaci\u00f3n de los datos de secuenciaci\u00f3n y la interacci\u00f3n de otros microorganismos, lo que permitir\u00e1 (2) la construcci\u00f3n de redes regulatorias post-transcripcionales miARN:ARNm asociadas a la adaptaci\u00f3n y supervivencia en los l\u00edmites de la vida.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI230206<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26210\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Red acad\u00e9mica internacional y multidisciplinaria para el fortalecimiento de la investigaci\u00f3n, docencia y formaci\u00f3n de capital humano avanzado en el desarrollo de habilidades matem\u00e1ticas y pensamiento matem\u00e1tico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26210\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26210\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La formaci\u00f3n de ciudadanos y ciudadanas capaces de afrontar los desaf\u00edos sociales y tecnol\u00f3gicos actuales requiere de capacidades matem\u00e1ticas que van m\u00e1s all\u00e1 del foco tradicional en contenidos espec\u00edficos y que den paso, en cambio, al desarrollo de habilidades matem\u00e1ticas y de pensamiento matem\u00e1tico. La realidad educativa chilena evidencia que los logros acad\u00e9micos en matem\u00e1tica han estado estancados por varios a\u00f1os, para luego sufrir un retroceso durante el per\u00edodo de pandemia. Si bien, desde 2012, los lineamientos curriculares de la asignatura de Matem\u00e1tica incluyen expl\u00edcitamente un foco en pensamiento matem\u00e1tico y objetivos de aprendizaje ligados a cuatro habilidades, docentes de todos los niveles educativos tienden a carecer de herramientas y competencias para desarrollarlas. Los numerosos desaf\u00edos de la formaci\u00f3n docente de pregrado, posgrado y formaci\u00f3n continua se profundizan al considerar la realidad de regiones distintas a la Metropolitana.\r\n\r\nEn este contexto, se destaca la creaci\u00f3n en 2015 de la Universidad de O\u0092Higgins como una decisi\u00f3n para potenciar el acceso a la educaci\u00f3n superior de una regi\u00f3n hist\u00f3ricamente postergada. En la actualidad, la Universidad de O\u0092Higgins cuenta con una carrera de Pedagog\u00eda en Matem\u00e1tica, formaci\u00f3n especializada en matem\u00e1tica en su carrera de Pedagog\u00eda en Educaci\u00f3n B\u00e1sica, y con un proyecto de programa de Mag\u00edster en Ense\u00f1anza y Aprendizaje de la Matem\u00e1tica cuya implementaci\u00f3n se proyecta para 2024. Alrededor de estos programas, se ha generado un equipo de investigadores(as) y docentes proveniente de diversas disciplinas \u0096grupo de investigaci\u00f3n GeaMat\u0096 que comparten un inter\u00e9s com\u00fan por mejorar la educaci\u00f3n matem\u00e1tica a trav\u00e9s de empoderar a los y las docentes con herramientas y competencias para el desarrollo de habilidades matem\u00e1ticas y el pensamiento matem\u00e1tico en distintos niveles del sistema educativo.\r\n\r\nLa presente propuesta busca consolidar estos v\u00ednculos a trav\u00e9s de la articulaci\u00f3n de una Red acad\u00e9mica multidisciplinaria, nacional e internacional, que potencie la investigaci\u00f3n, la docencia y la formaci\u00f3n de capital humano avanzado en educaci\u00f3n matem\u00e1tica, con foco particular en el estudio y desarrollo de habilidades matem\u00e1ticas y el pensamiento matem\u00e1tico. El equipo chileno, liderado por la Universidad de O\u0092Higgins con participaci\u00f3n de la Universidad Cat\u00f3lica de la Sant\u00edsima Concepci\u00f3n y la Universidad Metropolitana de Ciencias de la Educaci\u00f3n, confluir\u00e1 con un equipo de investigadores(as) de Espa\u00f1a, Costa Rica y B\u00e9lgica. Los miembros del equipo nacional cuentan con un historial de vinculaci\u00f3n previa con los(as) investigadores(as) del extranjero, que se extiende en varios casos por m\u00e1s de cinco a\u00f1os y se continuar\u00e1 articulando a trav\u00e9s de esta propuesta buscando potenciar la realizaci\u00f3n de iniciativas de investigaci\u00f3n y desarrollo conjuntas, as\u00ed como fortalecer la formaci\u00f3n de pre y posgrado en el \u00e1rea en las instituciones nacionales. En particular, se espera como resultados de este proyecto: 1) la consolidaci\u00f3n del grupo de investigaci\u00f3n GeaMat, creado recientemente en la Universidad de O\u0092Higgins, 2) el desarrollo de dos proyectos de investigaci\u00f3n de forma colaborativa en la Red, 3) la realizaci\u00f3n de reuniones de intercambio de experiencias de formaci\u00f3n de pre y posgrado en educaci\u00f3n matem\u00e1tica, y 4) la elaboraci\u00f3n de un documento con recomendaciones para el desarrollo de habilidades y pensamiento matem\u00e1tico en diferentes contextos educativos. De esta forma, se espera que esta propuesta produzca impactos tanto en el \u00e1mbito cient\u00edfico como en el \u00e1mbito educativo regional y nacional.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI230254<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024 - Junio 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26474\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desarrollo de la Electromovilidad en la Regi\u00f3n de O\u0092Higgins: Modelamiento, Gesti\u00f3n y Control\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26474\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26474\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Es un hecho aceptado en la comunidad cient\u00edfica que la emisi\u00f3n de CO2 es de los grandes responsables del calentamiento global. Por ello, ha habido muchas iniciativas para lograr la reducci\u00f3n de estas emisiones. Chile en particular, ha suscrito el compromiso de Carbono Neutralidad al 2050 y en ese contexto ha redactado una Estrategia Nacional de Electromovilidad para dar una hoja de ruta para estimular su adopci\u00f3n. Se espera que la transici\u00f3n hacia la electromovilidad y el fomento a la eficiencia energ\u00e9tica en transporte contribuir\u00e1 con cerca del 20% de las reducciones de emisiones de CO2 necesarias para lograr dicho compromiso.\r\nDado este contexto, esta propuesta abordar\u00e1 diversos aspectos relacionados con la electromovilidad, con foco en la regi\u00f3n de O\u0092higgins, donde la adopci\u00f3n ha sido m\u00e1s lenta de lo esperado, contando por ejemplo con reducida infraestructura de carga y venta de veh\u00edculos el\u00e9ctricos. Se destaca adem\u00e1s que previo a la inauguraci\u00f3n de la Universidad de O\u0092Higgins, no hab\u00eda una instituci\u00f3n que formara capital avanzado en estas tem\u00e1ticas.\r\nPor lo anterior, en este proyecto, se pondr\u00e1 especial atenci\u00f3n al modelamiento de bater\u00edas y\/o flotas de veh\u00edculos el\u00e9ctricos (VEs), de gesti\u00f3n y m\u00e9todos toma de decisiones en aplicaciones como gesti\u00f3n de flotas, interconexi\u00f3n de VEs en la red y asignaci\u00f3n de precios, y desarrollo de m\u00e9todos de control para motores el\u00e9ctricos, conversores, bater\u00edas y otros para electromovilidad.\r\nEl proyecto instalar\u00e1 y desarrollar\u00e1 en la Regi\u00f3n de O\u0092Higgins capacidades humanas avanzadas y fortalecer\u00e1 la cooperaci\u00f3n nacional e internacional en tem\u00e1ticas relacionadas con la electromovilidad. Se realizar\u00e1 difusi\u00f3n y divulgaci\u00f3n hacia la comunidad tanto en la Universidad de O\u0092Higgins (UOH) como en las instituciones asociadas, considerando actividades presenciales y online: Las actividades online se dejar\u00e1n abiertas al p\u00fablico en youtube.\r\nEsta propuesta contempla la ejecuci\u00f3n de 3 modalidades de vinculaci\u00f3n. En la primera modalidad (A) se realizar\u00e1n 3 viajes por parte de estudiantes de pre y posgrado y acad\u00e9micos a las instituciones extranjeras participantes del proyecto para capacitarse\/especializarse en modelamiento, gesti\u00f3n y control para electromovilidad. En la segunda modalidad (B) se realizar\u00e1n c\u00e1tedras y talleres online, para cursos de pre y posgrado en la Universidad de O\u0092Higgins y abiertos a todas las instituciones participantes del proyecto. En la tercera modalidad (C) se realizar\u00e1n 2 encuentros nacionales donde se realizar\u00e1n seminarios y talleres presenciales y reuniones de investigaci\u00f3n, donde est\u00e1n invitados alumnos de pre y posgrado de las instituciones participantes, y se realizar\u00e1 el Encuentro de Electromovilidad de O\u0092Higgins 2024, donde se invitar\u00e1 3 participantes extranjeros e investigadores nacionales participantes del proyecto, para difundir a la comunidad los avances en el \u00e1rea de la electromovilidad y estimular su adopci\u00f3n. Con este mismo prop\u00f3sito, se adquirir\u00e1 e instalar\u00e1 en la UOH 2 puntos de recarga de veh\u00edculos el\u00e9ctricos. Notar que actualmente la UOH tiene en su campus rancagua un cargador de bicicletas el\u00e9ctrico del tipo solar-e\u00f3lico para uso del estudiantado y la comunidad en general Finalmente, se buscar\u00e1 presentar las principales conclusiones y\/o resultados de este proyecto en conferencias cient\u00edficas o revistas nacionales y\/o internacionales.\r\nCon las acciones propuestas se busca fortalecer la colaboraci\u00f3n internacional, empoderar a las comunidades y promover el uso de nuevas tecnolog\u00edas de cero emisiones en medios de transporte en la regi\u00f3n y el pa\u00eds, al mismo tiempo que se reduce la generaci\u00f3n de gases de efecto invernadero, contribuyendo a lograr una sociedad energ\u00e9ticamente sustentable.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26500\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            MICCHI: Mecanismos e Incentivos Contra la Crisis HIdrica\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26500\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26500\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La crisis h\u00eddrica provocada por el calentamiento global es uno de los problemas m\u00e1s importantes que afectan a regiones agr\u00edcolas como la sexta Regi\u00f3n de O\u0092Higgins.  Este proyecto de vinculaci\u00f3n internacional tiene como objetivo principal investigar distintos mecanismos para la asignaci\u00f3n de recursos h\u00eddricos e \u00e9pocas de escasez. En particular, se analizar\u00e1 el caso en que se tienen multiples usos de agua: distintos tipos de industrias (cupr\u00edferas y agr\u00edcola por ejemplo) y uso urbano. Este proyecto de vinculaci\u00f3n internacional es liderado por el equipo nacional conformado por investigadores de la Universidad de O'Higgins y Universidad de Chile. Este proyecto incluye visitas del equipo nacional a los centros INRIA Sophia Antipolis, y INRAE en Montpellier, as\u00ed como la organizaci\u00f3n de un workshop en la Universidad de O\u0092Higgins.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI230206<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26584\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Red acad\u00e9mica internacional y multidisciplinaria para el fortalecimiento de la investigaci\u00f3n, docencia y formaci\u00f3n de capital humano avanzado en el desarrollo de habilidades matem\u00e1ticas y pensamiento matem\u00e1tico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26584\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26584\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La formaci\u00f3n de ciudadanos y ciudadanas capaces de afrontar los desaf\u00edos sociales y tecnol\u00f3gicos actuales requiere de capacidades matem\u00e1ticas que van m\u00e1s all\u00e1 del foco tradicional en contenidos espec\u00edficos y que den paso, en cambio, al desarrollo de habilidades matem\u00e1ticas y de pensamiento matem\u00e1tico. La realidad educativa chilena evidencia que los logros acad\u00e9micos en matem\u00e1tica han estado estancados por varios a\u00f1os, para luego sufrir un retroceso durante el per\u00edodo de pandemia. Si bien, desde 2012, los lineamientos curriculares de la asignatura de Matem\u00e1tica incluyen expl\u00edcitamente un foco en pensamiento matem\u00e1tico y objetivos de aprendizaje ligados a cuatro habilidades, docentes de todos los niveles educativos tienden a carecer de herramientas y competencias para desarrollarlas. Los numerosos desaf\u00edos de la formaci\u00f3n docente de pregrado, posgrado y formaci\u00f3n continua se profundizan al considerar la realidad de regiones distintas a la Metropolitana.\r\n\r\nEn este contexto, se destaca la creaci\u00f3n en 2015 de la Universidad de O\u0092Higgins como una decisi\u00f3n para potenciar el acceso a la educaci\u00f3n superior de una regi\u00f3n hist\u00f3ricamente postergada. En la actualidad, la Universidad de O\u0092Higgins cuenta con una carrera de Pedagog\u00eda en Matem\u00e1tica, formaci\u00f3n especializada en matem\u00e1tica en su carrera de Pedagog\u00eda en Educaci\u00f3n B\u00e1sica, y con un proyecto de programa de Mag\u00edster en Ense\u00f1anza y Aprendizaje de la Matem\u00e1tica cuya implementaci\u00f3n se proyecta para 2024. Alrededor de estos programas, se ha generado un equipo de investigadores(as) y docentes proveniente de diversas disciplinas \u0096grupo de investigaci\u00f3n GeaMat\u0096 que comparten un inter\u00e9s com\u00fan por mejorar la educaci\u00f3n matem\u00e1tica a trav\u00e9s de empoderar a los y las docentes con herramientas y competencias para el desarrollo de habilidades matem\u00e1ticas y el pensamiento matem\u00e1tico en distintos niveles del sistema educativo.\r\n\r\nLa presente propuesta busca consolidar estos v\u00ednculos a trav\u00e9s de la articulaci\u00f3n de una Red acad\u00e9mica multidisciplinaria, nacional e internacional, que potencie la investigaci\u00f3n, la docencia y la formaci\u00f3n de capital humano avanzado en educaci\u00f3n matem\u00e1tica, con foco particular en el estudio y desarrollo de habilidades matem\u00e1ticas y el pensamiento matem\u00e1tico. El equipo chileno, liderado por la Universidad de O\u0092Higgins con participaci\u00f3n de la Universidad Cat\u00f3lica de la Sant\u00edsima Concepci\u00f3n y la Universidad Metropolitana de Ciencias de la Educaci\u00f3n, confluir\u00e1 con un equipo de investigadores(as) de Espa\u00f1a, Costa Rica y B\u00e9lgica. Los miembros del equipo nacional cuentan con un historial de vinculaci\u00f3n previa con los(as) investigadores(as) del extranjero, que se extiende en varios casos por m\u00e1s de cinco a\u00f1os y se continuar\u00e1 articulando a trav\u00e9s de esta propuesta buscando potenciar la realizaci\u00f3n de iniciativas de investigaci\u00f3n y desarrollo conjuntas, as\u00ed como fortalecer la formaci\u00f3n de pre y posgrado en el \u00e1rea en las instituciones nacionales. En particular, se espera como resultados de este proyecto: 1) la consolidaci\u00f3n del grupo de investigaci\u00f3n GeaMat, creado recientemente en la Universidad de O\u0092Higgins, 2) el desarrollo de dos proyectos de investigaci\u00f3n de forma colaborativa en la Red, 3) la realizaci\u00f3n de reuniones de intercambio de experiencias de formaci\u00f3n de pre y posgrado en educaci\u00f3n matem\u00e1tica, y 4) la elaboraci\u00f3n de un documento con recomendaciones para el desarrollo de habilidades y pensamiento matem\u00e1tico en diferentes contextos educativos. De esta forma, se espera que esta propuesta produzca impactos tanto en el \u00e1mbito cient\u00edfico como en el \u00e1mbito educativo regional y nacional.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 230157<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024 - Junio 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26585\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Reduciendo las desigualdades educativas a trav\u00e9s de la relaci\u00f3n entre familia y escuela\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26585\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26585\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetivo principal de este proyecto es analizar y comprender c\u00f3mo la interacci\u00f3n entre\r\nescuela y familia puede generar altas expectativas compartidas para reducir las brechas\r\neducativas. Esto considerando dos perspectivas, una local y aplicada y otra global y con foco\r\nen el desarrollo de conocimiento b\u00e1sico. Desde la perspectiva local, tenemos que Chile, y en\r\nparticular la Regi\u00f3n de O'Higgins, presenta desaf\u00edos complejos en t\u00e9rminos de desigualdades\r\neducativas asociadas a factores socioecon\u00f3micos y de ruralidad. Las brechas educativas son\r\nun problema persistente, asociado a un sistema educacional extremadamente segregado. Por\r\notra parte, desde una perspectiva global, las desigualdades educativas son un problema\r\nmunidal, con especificidades de cada contexto, y es necesario entender qu\u00e9 tipos de relaciones\r\nfamilia-escuela permiten reducir desigualdades. Adem\u00e1s, uno de los objetivos de desarrollo\r\nsostenible es alcanzar una educaci\u00f3n de calidad para todos y todas, y este proyecto apunta al\r\nlogro de ese objetivo[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI230254<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024 - Junio 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26595\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desarrollo de la Electromovilidad en la Regi\u00f3n de O\u0092Higgins: Modelamiento, Gesti\u00f3n y Control\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26595\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26595\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Es un hecho aceptado en la comunidad cient\u00edfica que la emisi\u00f3n de CO2 es de los grandes responsables del calentamiento global. Por ello, ha habido muchas iniciativas para lograr la reducci\u00f3n de estas emisiones. Chile en particular, ha suscrito el compromiso de Carbono Neutralidad al 2050 y en ese contexto ha redactado una Estrategia Nacional de Electromovilidad para dar una hoja de ruta para estimular su adopci\u00f3n. Se espera que la transici\u00f3n hacia la electromovilidad y el fomento a la eficiencia energ\u00e9tica en transporte contribuir\u00e1 con cerca del 20% de las reducciones de emisiones de CO2 necesarias para lograr dicho compromiso.\r\nDado este contexto, esta propuesta abordar\u00e1 diversos aspectos relacionados con la electromovilidad, con foco en la regi\u00f3n de O\u0092higgins, donde la adopci\u00f3n ha sido m\u00e1s lenta de lo esperado, contando por ejemplo con reducida infraestructura de carga y venta de veh\u00edculos el\u00e9ctricos. Se destaca adem\u00e1s que previo a la inauguraci\u00f3n de la Universidad de O\u0092Higgins, no hab\u00eda una instituci\u00f3n que formara capital avanzado en estas tem\u00e1ticas.\r\nPor lo anterior, en este proyecto, se pondr\u00e1 especial atenci\u00f3n al modelamiento de bater\u00edas y\/o flotas de veh\u00edculos el\u00e9ctricos (VEs), de gesti\u00f3n y m\u00e9todos toma de decisiones en aplicaciones como gesti\u00f3n de flotas, interconexi\u00f3n de VEs en la red y asignaci\u00f3n de precios, y desarrollo de m\u00e9todos de control para motores el\u00e9ctricos, conversores, bater\u00edas y otros para electromovilidad.\r\nEl proyecto instalar\u00e1 y desarrollar\u00e1 en la Regi\u00f3n de O\u0092Higgins capacidades humanas avanzadas y fortalecer\u00e1 la cooperaci\u00f3n nacional e internacional en tem\u00e1ticas relacionadas con la electromovilidad. Se realizar\u00e1 difusi\u00f3n y divulgaci\u00f3n hacia la comunidad tanto en la Universidad de O\u0092Higgins (UOH) como en las instituciones asociadas, considerando actividades presenciales y online: Las actividades online se dejar\u00e1n abiertas al p\u00fablico en youtube.\r\nEsta propuesta contempla la ejecuci\u00f3n de 3 modalidades de vinculaci\u00f3n. En la primera modalidad (A) se realizar\u00e1n 3 viajes por parte de estudiantes de pre y posgrado y acad\u00e9micos a las instituciones extranjeras participantes del proyecto para capacitarse\/especializarse en modelamiento, gesti\u00f3n y control para electromovilidad. En la segunda modalidad (B) se realizar\u00e1n c\u00e1tedras y talleres online, para cursos de pre y posgrado en la Universidad de O\u0092Higgins y abiertos a todas las instituciones participantes del proyecto. En la tercera modalidad (C) se realizar\u00e1n 2 encuentros nacionales donde se realizar\u00e1n seminarios y talleres presenciales y reuniones de investigaci\u00f3n, donde est\u00e1n invitados alumnos de pre y posgrado de las instituciones participantes, y se realizar\u00e1 el Encuentro de Electromovilidad de O\u0092Higgins 2024, donde se invitar\u00e1 3 participantes extranjeros e investigadores nacionales participantes del proyecto, para difundir a la comunidad los avances en el \u00e1rea de la electromovilidad y estimular su adopci\u00f3n. Con este mismo prop\u00f3sito, se adquirir\u00e1 e instalar\u00e1 en la UOH 2 puntos de recarga de veh\u00edculos el\u00e9ctricos. Notar que actualmente la UOH tiene en su campus rancagua un cargador de bicicletas el\u00e9ctrico del tipo solar-e\u00f3lico para uso del estudiantado y la comunidad en general Finalmente, se buscar\u00e1 presentar las principales conclusiones y\/o resultados de este proyecto en conferencias cient\u00edficas o revistas nacionales y\/o internacionales.\r\nCon las acciones propuestas se busca fortalecer la colaboraci\u00f3n internacional, empoderar a las comunidades y promover el uso de nuevas tecnolog\u00edas de cero emisiones en medios de transporte en la regi\u00f3n y el pa\u00eds, al mismo tiempo que se reduce la generaci\u00f3n de gases de efecto invernadero, contribuyendo a lograr una sociedad energ\u00e9ticamente sustentable.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26602\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            MICCHI: Mecanismos e Incentivos Contra la Crisis HIdrica\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26602\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26602\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La crisis h\u00eddrica provocada por el calentamiento global es uno de los problemas m\u00e1s importantes que afectan a regiones agr\u00edcolas como la sexta Regi\u00f3n de O\u0092Higgins.  Este proyecto de vinculaci\u00f3n internacional tiene como objetivo principal investigar distintos mecanismos para la asignaci\u00f3n de recursos h\u00eddricos e \u00e9pocas de escasez. En particular, se analizar\u00e1 el caso en que se tienen multiples usos de agua: distintos tipos de industrias (cupr\u00edferas y agr\u00edcola por ejemplo) y uso urbano. Este proyecto de vinculaci\u00f3n internacional es liderado por el equipo nacional conformado por investigadores de la Universidad de O'Higgins y Universidad de Chile. Este proyecto incluye visitas del equipo nacional a los centros INRIA Sophia Antipolis, y INRAE en Montpellier, as\u00ed como la organizaci\u00f3n de un workshop en la Universidad de O\u0092Higgins.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI230206<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26698\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Red acad\u00e9mica internacional y multidisciplinaria para el fortalecimiento de la investigaci\u00f3n, docencia y formaci\u00f3n de capital humano avanzado en el desarrollo de habilidades matem\u00e1ticas y pensamiento matem\u00e1tico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26698\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26698\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La formaci\u00f3n de ciudadanos y ciudadanas capaces de afrontar los desaf\u00edos sociales y tecnol\u00f3gicos actuales requiere de capacidades matem\u00e1ticas que van m\u00e1s all\u00e1 del foco tradicional en contenidos espec\u00edficos y que den paso, en cambio, al desarrollo de habilidades matem\u00e1ticas y de pensamiento matem\u00e1tico. La realidad educativa chilena evidencia que los logros acad\u00e9micos en matem\u00e1tica han estado estancados por varios a\u00f1os, para luego sufrir un retroceso durante el per\u00edodo de pandemia. Si bien, desde 2012, los lineamientos curriculares de la asignatura de Matem\u00e1tica incluyen expl\u00edcitamente un foco en pensamiento matem\u00e1tico y objetivos de aprendizaje ligados a cuatro habilidades, docentes de todos los niveles educativos tienden a carecer de herramientas y competencias para desarrollarlas. Los numerosos desaf\u00edos de la formaci\u00f3n docente de pregrado, posgrado y formaci\u00f3n continua se profundizan al considerar la realidad de regiones distintas a la Metropolitana.\r\n\r\nEn este contexto, se destaca la creaci\u00f3n en 2015 de la Universidad de O\u0092Higgins como una decisi\u00f3n para potenciar el acceso a la educaci\u00f3n superior de una regi\u00f3n hist\u00f3ricamente postergada. En la actualidad, la Universidad de O\u0092Higgins cuenta con una carrera de Pedagog\u00eda en Matem\u00e1tica, formaci\u00f3n especializada en matem\u00e1tica en su carrera de Pedagog\u00eda en Educaci\u00f3n B\u00e1sica, y con un proyecto de programa de Mag\u00edster en Ense\u00f1anza y Aprendizaje de la Matem\u00e1tica cuya implementaci\u00f3n se proyecta para 2024. Alrededor de estos programas, se ha generado un equipo de investigadores(as) y docentes proveniente de diversas disciplinas \u0096grupo de investigaci\u00f3n GeaMat\u0096 que comparten un inter\u00e9s com\u00fan por mejorar la educaci\u00f3n matem\u00e1tica a trav\u00e9s de empoderar a los y las docentes con herramientas y competencias para el desarrollo de habilidades matem\u00e1ticas y el pensamiento matem\u00e1tico en distintos niveles del sistema educativo.\r\n\r\nLa presente propuesta busca consolidar estos v\u00ednculos a trav\u00e9s de la articulaci\u00f3n de una Red acad\u00e9mica multidisciplinaria, nacional e internacional, que potencie la investigaci\u00f3n, la docencia y la formaci\u00f3n de capital humano avanzado en educaci\u00f3n matem\u00e1tica, con foco particular en el estudio y desarrollo de habilidades matem\u00e1ticas y el pensamiento matem\u00e1tico. El equipo chileno, liderado por la Universidad de O\u0092Higgins con participaci\u00f3n de la Universidad Cat\u00f3lica de la Sant\u00edsima Concepci\u00f3n y la Universidad Metropolitana de Ciencias de la Educaci\u00f3n, confluir\u00e1 con un equipo de investigadores(as) de Espa\u00f1a, Costa Rica y B\u00e9lgica. Los miembros del equipo nacional cuentan con un historial de vinculaci\u00f3n previa con los(as) investigadores(as) del extranjero, que se extiende en varios casos por m\u00e1s de cinco a\u00f1os y se continuar\u00e1 articulando a trav\u00e9s de esta propuesta buscando potenciar la realizaci\u00f3n de iniciativas de investigaci\u00f3n y desarrollo conjuntas, as\u00ed como fortalecer la formaci\u00f3n de pre y posgrado en el \u00e1rea en las instituciones nacionales. En particular, se espera como resultados de este proyecto: 1) la consolidaci\u00f3n del grupo de investigaci\u00f3n GeaMat, creado recientemente en la Universidad de O\u0092Higgins, 2) el desarrollo de dos proyectos de investigaci\u00f3n de forma colaborativa en la Red, 3) la realizaci\u00f3n de reuniones de intercambio de experiencias de formaci\u00f3n de pre y posgrado en educaci\u00f3n matem\u00e1tica, y 4) la elaboraci\u00f3n de un documento con recomendaciones para el desarrollo de habilidades y pensamiento matem\u00e1tico en diferentes contextos educativos. De esta forma, se espera que esta propuesta produzca impactos tanto en el \u00e1mbito cient\u00edfico como en el \u00e1mbito educativo regional y nacional.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 23-MATH-09<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024 - Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26708\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26708\" aria-expanded=\"false\" aria-controls=\"collapse-26708\">\n                                            Matrices, Optimization and Randomness with applications to Data Science\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26708\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26708\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The research project \"Matrices, Optimization, and Randomness with Applications in Data Science (MORA-DataS)\" is composed of research teams from Bolivia, Chile, France, and Peru. This project is funded by the regional program MATH-Amsud in cooperation with UMSA (Bolivia), ANID, CMM (Chile), MEAE (France), and CONCYTEC (Peru). \r\nThe aim of this project is to study diverse optimization models, deterministic and stochastic, and to investigate various problems in matrix analysis with potential applications in data science. Some of the research topics are computing angles between convex cones, inverse eigenvalue problems, proximal algorithms for symmetric cone optimization, nonlinear second-order cone programming problems, nonsmooth joint chance constrained optimization problems, and Euclidean Jordan algebras for optimization.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> #635276<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024 - Noviembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26759\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            CONCURSO DE APOYO A CENTROS DE EXCELENCIA EN INVESTIGACI\u00d3N EN \u00c1REAS PRIORITARIAS &#8211; FONDAP 2023 \u0096 SCIA\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26759\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26759\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proceso de renovaci\u00f3n de Proyecto FONDAP (Fondo Puente) del Centro de Estudios de Conflicto y Cohesi\u00f3n Social (COES).[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI230047<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26903\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Vinculaci\u00f3n internacional para la evaluaci\u00f3n de la capacidad centinela de moluscos bivalvos filtradores en el monitoreo de contaminantes emergentes en \u00e1reas costeras marinas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26903\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26903\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Vinculaci\u00f3n internacional para la evaluaci\u00f3n de la capacidad centinela de moluscos bivalvos filtradores en el monitoreo de contaminantes emergentes en \u00e1reas costeras marinas[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26959\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Evaluar para reactivar el aprendizaje: explorando la valoraci\u00f3n y expectativas de docentes y directivos de ense\u00f1anza media sobre distintas fuentes de evaluaci\u00f3n de aprendizaje\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26959\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26959\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]A pesar de lo que establecen las normativas y orientaciones de pol\u00edtica, existe poco conocimiento respecto de qu\u00e9 evaluaciones son utilizadas por docentes y directivos de establecimientos educacionales y para qu\u00e9 fines. La informaci\u00f3n que entregan estas fuentes es clave para que los establecimientos tomen decisiones pedag\u00f3gicas y monitoreen el progreso de sus estudiantes en respuesta a necesidades internas de su comunidad y externas de otros niveles del sistema escolar (intermedio, nacional). Esto se suma a los resultados SIMCE 2022, presentados en el mes de junio 2023 por la Agencia de Calidad, que muestran el aumento de brechas de g\u00e9nero y socioecon\u00f3micas, particularmente entre estudiantes de segundo medio, producto de la pandemia. Por lo tanto, es necesario investigar la valoraci\u00f3n y expectativas de docentes y directivos respecto del uso, pertinencia y relevancia de distintas fuentes de evaluaci\u00f3n. Se propone que el conocimiento de las instancias evaluativas que son consideradas como fuentes de informaci\u00f3n valiosa para la toma de decisiones pedag\u00f3gicas podr\u00eda contribuir al dise\u00f1o, gesti\u00f3n y acompa\u00f1amiento de pol\u00edticas educativas futuras relativas a la evaluaci\u00f3n y a la reactivaci\u00f3n de los aprendizajes.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI230206<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26975\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Red acad\u00e9mica internacional y multidisciplinaria para el fortalecimiento de la investigaci\u00f3n, docencia y formaci\u00f3n de capital humano avanzado en el desarrollo de habilidades matem\u00e1ticas y pensamiento matem\u00e1tico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26975\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26975\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La formaci\u00f3n de ciudadanos y ciudadanas capaces de afrontar los desaf\u00edos sociales y tecnol\u00f3gicos actuales requiere de capacidades matem\u00e1ticas que van m\u00e1s all\u00e1 del foco tradicional en contenidos espec\u00edficos y que den paso, en cambio, al desarrollo de habilidades matem\u00e1ticas y de pensamiento matem\u00e1tico. La realidad educativa chilena evidencia que los logros acad\u00e9micos en matem\u00e1tica han estado estancados por varios a\u00f1os, para luego sufrir un retroceso durante el per\u00edodo de pandemia. Si bien, desde 2012, los lineamientos curriculares de la asignatura de Matem\u00e1tica incluyen expl\u00edcitamente un foco en pensamiento matem\u00e1tico y objetivos de aprendizaje ligados a cuatro habilidades, docentes de todos los niveles educativos tienden a carecer de herramientas y competencias para desarrollarlas. Los numerosos desaf\u00edos de la formaci\u00f3n docente de pregrado, posgrado y formaci\u00f3n continua se profundizan al considerar la realidad de regiones distintas a la Metropolitana.\r\n\r\nEn este contexto, se destaca la creaci\u00f3n en 2015 de la Universidad de O\u0092Higgins como una decisi\u00f3n para potenciar el acceso a la educaci\u00f3n superior de una regi\u00f3n hist\u00f3ricamente postergada. En la actualidad, la Universidad de O\u0092Higgins cuenta con una carrera de Pedagog\u00eda en Matem\u00e1tica, formaci\u00f3n especializada en matem\u00e1tica en su carrera de Pedagog\u00eda en Educaci\u00f3n B\u00e1sica, y con un proyecto de programa de Mag\u00edster en Ense\u00f1anza y Aprendizaje de la Matem\u00e1tica cuya implementaci\u00f3n se proyecta para 2024. Alrededor de estos programas, se ha generado un equipo de investigadores(as) y docentes proveniente de diversas disciplinas \u0096grupo de investigaci\u00f3n GeaMat\u0096 que comparten un inter\u00e9s com\u00fan por mejorar la educaci\u00f3n matem\u00e1tica a trav\u00e9s de empoderar a los y las docentes con herramientas y competencias para el desarrollo de habilidades matem\u00e1ticas y el pensamiento matem\u00e1tico en distintos niveles del sistema educativo.\r\n\r\nLa presente propuesta busca consolidar estos v\u00ednculos a trav\u00e9s de la articulaci\u00f3n de una Red acad\u00e9mica multidisciplinaria, nacional e internacional, que potencie la investigaci\u00f3n, la docencia y la formaci\u00f3n de capital humano avanzado en educaci\u00f3n matem\u00e1tica, con foco particular en el estudio y desarrollo de habilidades matem\u00e1ticas y el pensamiento matem\u00e1tico. El equipo chileno, liderado por la Universidad de O\u0092Higgins con participaci\u00f3n de la Universidad Cat\u00f3lica de la Sant\u00edsima Concepci\u00f3n y la Universidad Metropolitana de Ciencias de la Educaci\u00f3n, confluir\u00e1 con un equipo de investigadores(as) de Espa\u00f1a, Costa Rica y B\u00e9lgica. Los miembros del equipo nacional cuentan con un historial de vinculaci\u00f3n previa con los(as) investigadores(as) del extranjero, que se extiende en varios casos por m\u00e1s de cinco a\u00f1os y se continuar\u00e1 articulando a trav\u00e9s de esta propuesta buscando potenciar la realizaci\u00f3n de iniciativas de investigaci\u00f3n y desarrollo conjuntas, as\u00ed como fortalecer la formaci\u00f3n de pre y posgrado en el \u00e1rea en las instituciones nacionales. En particular, se espera como resultados de este proyecto: 1) la consolidaci\u00f3n del grupo de investigaci\u00f3n GeaMat, creado recientemente en la Universidad de O\u0092Higgins, 2) el desarrollo de dos proyectos de investigaci\u00f3n de forma colaborativa en la Red, 3) la realizaci\u00f3n de reuniones de intercambio de experiencias de formaci\u00f3n de pre y posgrado en educaci\u00f3n matem\u00e1tica, y 4) la elaboraci\u00f3n de un documento con recomendaciones para el desarrollo de habilidades y pensamiento matem\u00e1tico en diferentes contextos educativos. De esta forma, se espera que esta propuesta produzca impactos tanto en el \u00e1mbito cient\u00edfico como en el \u00e1mbito educativo regional y nacional.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> AG 401561\/2023-2. Chamada Chamada Universal CNPq\/MCTI N\u00ba 10\/2023 - Faixa B - Grupos Consolidados<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27009\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            A intera\u00e7\u00e3o sil\u00edcio e pot\u00e1ssio modula a efici\u00eancia do uso da \u00e1gua favorecendo a sustentabilidade de cultivos anuais irrigados\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27009\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27009\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]O cultivo irrigado de culturas anuais como milho e feij\u00e3o tem se expandido nos \u00faltimos anos ao mesmo tempo com a restri\u00e7\u00e3o h\u00eddrica dada as mudan\u00e7as clim\u00e1ticas, por isso \u00e9 primordial pesquisas estrat\u00e9gicas para aumentar efici\u00eancia do uso da \u00e1gua com sustentabilidade. Para isso, a nutri\u00e7\u00e3o de plantas equilibrada pode contribuir para aumentar a efici\u00eancia no uso da \u00e1gua, em especial com fornecimento de sil\u00edcio (Si) e de pot\u00e1ssio (K), mas ainda \u00e9 desconhecida essa sinergia especialmente em cultivos fertirrigados. Dessa forma, \u00e9 importante ter respostas para as seguintes hip\u00f3teses: i) existe uma dose de Si \u00f3tima e econ\u00f4mica para fertirriga\u00e7\u00e3o e os teores de Si no solo\/solu\u00e7\u00e3o e foliar adequado para seu uso fundamentado, mas depende da esp\u00e9cie cultivada; ii) o Si \u00e9 um elemento multiestresse ao mitigar danos causados pelo d\u00e9ficit h\u00eddrico moderado e severo associado ao estresse por defici\u00eancia de K (comum em solos tropicais) em plantas de milho e feij\u00e3o; iii) o fornecimento \u00f3timo de Si via fertirriga\u00e7\u00e3o associado ao K \u00f3timo pode diminuir a necessidade h\u00eddrica das duas esp\u00e9cies mantendo alta produtividade; iv) al\u00e9m disso, os dois elementos interferem na decomposi\u00e7\u00e3o da biomassa vegetal diminuindo a emiss\u00e3o de CO2. Assim, os tratamentos consistir\u00e3o de fatorial 3x2x4, tr\u00eas regimes h\u00eddricos: 80% (sem d\u00e9ficit), 60% (d\u00e9ficit h\u00eddrico moderado) e 40% (d\u00e9ficit h\u00eddrico severo) da capacidade de reten\u00e7\u00e3o de \u00e1gua no solo; duas fertiliza\u00e7\u00f5es pot\u00e1ssicas: defici\u00eancia (zero de K) e sufici\u00eancia de K, e quatro doses de Si fornecidas via fertirriga\u00e7\u00e3o: 0; 4; 8 e 12 kg ha-1 . Para testar essas hip\u00f3teses ser\u00e3o realizados dois experimentos com milho e feij\u00e3o objetivando-se estabelecer doses de Si via fertirriga\u00e7\u00e3o e sua sinergia com K em tr\u00eas regimes h\u00eddricos em aspectos fisiol\u00f3gicos, bioqu\u00edmicos, nutricionais e ambientais para fundamentar estrat\u00e9gia para uso eficiente da \u00e1gua em sistema de cultivo irrigado[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> (Projeto CNPq Proc. 442435\/2023-1)<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Conselho Nacional de Desenvolvimento Cient\u00edfico e Tecnol\u00f3gico (CNPq)- Aux\u00edlio financeiro.<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27010\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27010\" aria-expanded=\"false\" aria-controls=\"collapse-27010\">\n                                            Uso de componentes bi\u00f3ticos e abi\u00f3ticos no solo para melhorar a efici\u00eancia do uso de nutrientes e \u00e1gua em culturas anuais &#8211; Coopera\u00e7\u00e3o Brasil, Chile, Espanha e Portugual\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27010\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27010\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El riego de cultivos anuales se ha expandido en los \u00faltimos a\u00f1os a la par de las restricciones h\u00eddricas por el cambio clim\u00e1tico, por lo que la investigaci\u00f3n estrat\u00e9gica para aumentar la eficiencia y la sostenibilidad en el uso del agua es fundamental. Para ello, una nutrici\u00f3n vegetal equilibrada puede contribuir a aumentar la eficiencia en el uso del agua, especialmente con el aporte de silicio, pero esta sinergia a\u00fan es desconocida, especialmente en cultivos fertirrigados. Por lo tanto, es importante tener respuestas a las siguientes hip\u00f3tesis: i) existe una dosis \u00f3ptima y econ\u00f3mica de Si para fertirrigaci\u00f3n y los contenidos de Si en suelo\/soluci\u00f3n y foliar adecuados para su uso fundamentado, pero depende de la especie cultivada; ii) El suministro \u00f3ptimo de Si mediante fertirrigaci\u00f3n asociado puede reducir las necesidades de agua de ambas de los cultivos manteniendo una alta productividad. Para probar estas hip\u00f3tesis, se realizar\u00e1n dos experimentos con ma\u00edz y frijol, con el objetivo de establecer dosis de Si v\u00eda fertirrigaci\u00f3n y su sinergia con K en tres reg\u00edmenes h\u00eddricos en aspectos fisiol\u00f3gicos, bioqu\u00edmicos, nutricionales y ambientales para apoyar una estrategia de uso eficiente de agua en un sistema de suministro de agua, cultivo de regad\u00edo.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024 - Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27033\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            An\u00e1lisis multi\u00f3mico de redes reguladoras post-transcripcionales microARN- ARNm en el m\u00fasculo esquel\u00e9tico humano envejecido.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27033\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27033\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Durante las \u00faltimas d\u00e9cadas, la expectativa de vida promedio ha aumentado dram\u00e1ticamente, mientras\r\nque la salud no ha aumentado proporcionalmente. Para Chile se espera que para el 2050 el n\u00famero de\r\nadultos mayores superar\u00e1 el 30% de la poblaci\u00f3n con un incremento del 109% respecto al 2015,\r\nsuperando el 75% proyectado para la poblaci\u00f3n mundial. Entender el proceso de envejecimeinto y\r\nencontrar marcadores biol\u00f3gicos con capacidad diagn\u00f3stica y pron\u00f3stica, permitir\u00e1 promover estrategias\r\npara aumentar el n\u00famero de a\u00f1os de vida saludable, disminuyendo los gastos en salud asociado al\r\nenvejecimiento.\r\nVarios estudios han permitido avanzar y entender los mecanismos moleculares de p\u00e9rdidad de funci\u00f3n\r\nmuscular durante el evenjecimiento, m\u00e1s conocida como sarcopenia. Sin embargo, la complejidad del\r\nproceso y el insuficiente conocimiento de los mecanismos subjacentes dificultan el dise\u00f1o de estrategias\r\nterap\u00e9uticas eficaces. Hasta el momento, la actividad f\u00edsica y el ejercicio siguen siendo la estrategia m\u00e1s\r\neficaz para previnir y tratar la sarcopenia. Por lo cual, identificar nuevos biomarcadores musculares en\r\ncombinaci\u00f3n con marcadores cl\u00ednicos bien establecidos de par\u00e1metros f\u00edsicos y funcionales, fortalecer\u00eda\r\nla actual evaluaci\u00f3n geri\u00e1trica, al utilizar un enfoque interdiciplinario.\r\nLos microRNA (miRNA, 18\u009625 nt de largo) han ganado inter\u00e9s debido a que son mol\u00e9culas altamente\r\nconservadas en todas las especies, y act\u00faan como reguladores positivos y\/o negativos de la expresi\u00f3n\r\ng\u00e9nica. Entender la relaci\u00f3n reguladora directa entre los miARN y el ARN mensajero (mRNA) desempe\u00f1a\r\nen el m\u00fasculo esquel\u00e9tica es fundamentaltanto para el proceso de transcripci\u00f3n del ARNm y traducci\u00f3n\r\nde prote\u00ednas como para entender el deterioro de la funci\u00f3n muscular. Sin embargo, la regulaci\u00f3n de la\r\nred post-transcripcional miARN-ARNm y los mecanismos gen\u00e9ticos involucrados en el proceso de\r\nenvejecimiento del m\u00fasculo esquel\u00e9tico humano est\u00e1n lejos de ser elucidados.\r\nEn el presente estudio, nuestro objetivo es explorar e integrar coperfiles emparejados de miARN y ARNm\r\ndurante la p\u00e9rdida de funci\u00f3n muscular producidad durante el envejecimeinto en personas mayores. Este\r\nan\u00e1lisis integral permitir\u00e1 la identificaci\u00f3n de nuevos blancos de miARN y estrategias reguladoras que\r\ncontrolan la expresi\u00f3n g\u00e9nica en la p\u00e9rdidad de funci\u00f3n del m\u00fasculo esquel\u00e9tico y c\u00f3mo \u00e9stas son\r\nmodificadas por el entrenamiento de fuerza.\r\nSe hipotetiza que existen redes de regulaci\u00f3n post-transcripcional miRNA\/mRNA que se expresan de\r\nmanera diferencial en el m\u00fasculo esquel\u00e9tico de personas j\u00f3venes y personas mayores, que estar\u00edan\r\nasociadas con cambios en la funci\u00f3n muscular durante el envejecimiento. Adem\u00e1s, el entrenamiento de\r\nfuerza modifica estas redes de regulaci\u00f3n, lo que podr\u00eda contribuir a la mejora de la funci\u00f3n muscular y la\r\nprevenci\u00f3n o atenuaci\u00f3n de la sarcopenia.\r\nObjetivos generales\r\n- Identificar las redes de regulaci\u00f3n post-transcripcional miRNA\/mRNA involucradas en la\r\np\u00e9rdida de funci\u00f3n musclular en personas mayores que son moduladas por un entrenamiento\r\nde fuerza, para proponer nuevos biomarcadores de funci\u00f3n muscular durante el\r\nenvejecimeinto que se correlacionan con par\u00e1metros cl\u00ednicos\/funcionales.\r\nObjetivos espec\u00edficos\r\n1. Determinar las redes de regulaci\u00f3n post-transcripcional miRNA\/mRNA que se expresan\r\ndiferencialmente en el m\u00fasculo esquel\u00e9tico de personas j\u00f3venes y personas mayores.\r\n2. Identificar las redes de regulaci\u00f3n post-transcripcional miRNA\/mRNA que se modifican\r\ndespu\u00e9s de 12 semanas de entrenamiento de fuerza en personas mayores\r\n3. Correlacionar las redes miRNA\/mRNA identificadas con par\u00e1metros bioqu\u00edmicos, f\u00edsicos y\r\nfuncionales de funci\u00f3n muscular, antes y despu\u00e9s de 12 semanas de entrenamiento de\r\nfuerza en personas mayores\r\nEste proyecto busca Identificar nuevos biomarcadores de funci\u00f3n muscular durante el envejecimiento,\r\npodr\u00edan ser utilizados en futuros estudios y en la pr\u00e1ctica cl\u00ednica para evaluar la salud muscular en\r\npersonas mayores. Adem\u00e1s, de contribuir a una mejor comprensi\u00f3n de los mecanismos moleculares que\r\nsubyacen a la p\u00e9rdida de masa muscular en el envejecimiento y c\u00f3mo la intervenci\u00f3n del entrenamiento\r\nde fuerza puede modificar esos mecanismos. Finalmente, el uso de tecnolog\u00edas avanzadas de\r\nsecuenciaci\u00f3n (mARN y miARN) y bioinform\u00e1tica permitir\u00e1 impulsar el desarrollo y la mejora de t\u00e9cnicas\r\nde secuenciaci\u00f3n y an\u00e1lisis de datos en el campo de la gen\u00f3mica y la transcript\u00f3mica en el \u00e1rea del\r\nenvejecimiento, como tambi\u00e9n, promover la colaboraci\u00f3n a nivel nacional e internacional a trav\u00e9s de las\r\nbases de datos y recursos bioinform\u00e1ticos generados que estar\u00e1n a disposici\u00f3n de investigadores del \u00e1rea.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 112031001-PI2404<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2024 - Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27038\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Construcci\u00f3n in-silico de redes reguladoras miRNA:mRNA de especies vegetales end\u00e9micas del desierto de Atacama en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27038\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27038\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetivo principal de esta propuesta es estudiar las redes de regulaci\u00f3n post-transcripcionale de miARNs en especies vegetales del desierto de Atacama, su adaptaci\u00f3n a ambientes extremos e interacci\u00f3n con el medio donde habita. \r\n\r\nSe propone  un enfoque que integra (1) la implementaci\u00f3n de un nuevo m\u00e9todo computacional para predecir estas interacciones miARN:ARNm que permita integrar informaci\u00f3n de los datos de secuenciaci\u00f3n y la interacci\u00f3n de otros microorganismos, lo que permitir\u00e1 (2) la construcci\u00f3n de redes regulatorias post-transcripcionales miARN:ARNm asociadas a la adaptaci\u00f3n y supervivencia en los l\u00edmites de la vida.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ID: 955576 - Resoluci\u00f3n: 5461-2023<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2023 - Enero 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Servicio Nacional de la Discapacidad (SENADIS)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26689\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26689\" aria-expanded=\"false\" aria-controls=\"collapse-26689\">\n                                            Programa de Participaci\u00f3n Inclusiva Territorial 2023 en la Macrozona Austral. Desarrollo de herramientas para la implementaci\u00f3n.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26689\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26689\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Convenio de transferencia Programa Participaci\u00f3n Inclusiva Territorial, a\u00f1o 2023, entre Servicio Nacional de la Discapacidad y Universidad de O\u0092Higgins. \"Programa de participaci\u00f3n inclusiva en la Macrozona Austral: desarrollo de herramientas para la implementaci\u00f3n\". El presente proyecto tiene el objetivo de fortalecer el proceso de inclusi\u00f3n y participaci\u00f3n de las organizaciones de y para personas con discapacidad, cuidadoras\/es y sus familiares, mediante la entrega de herramientas pr\u00e1cticas a las organizaciones, la promoci\u00f3n de la asociatividad y el posicionamiento de la tem\u00e1tica con los actores relevantes en el territorio de la Macrozona Austral. Para esto propone alcanzar su objetivo general y sus objetivos espec\u00edficos a trav\u00e9s  de aplicaci\u00f3n de m\u00e9todos mixtos multic\u00e9ntricos e intervenciones de base comunitaria, estructurados en cuatro l\u00edneas de trabajo principales, 1) fortalecimiento de las organizaciones en el territorio a partir de la realizaci\u00f3n de un catastro regional y de diagn\u00f3sticos participativos, 2) escuela de gesti\u00f3n social y territorial, 3) actividades de difusi\u00f3n y 4) sistematizaci\u00f3n y evaluaci\u00f3n desde un enfoque de ciencias de la implementaci\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ID: 955576 - Resoluci\u00f3n: 5461-2023<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2023 - Enero 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Servicio Nacional de la Discapacidad (SENADIS)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26841\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26841\" aria-expanded=\"false\" aria-controls=\"collapse-26841\">\n                                            Programa de Participaci\u00f3n Inclusiva Territorial 2023 en la Macrozona Austral. Desarrollo de herramientas para la implementaci\u00f3n.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26841\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26841\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Convenio de transferencia Programa Participaci\u00f3n Inclusiva Territorial, a\u00f1o 2023, entre Servicio Nacional de la Discapacidad y Universidad de O\u0092Higgins. \"Programa de participaci\u00f3n inclusiva en la Macrozona Austral: desarrollo de herramientas para la implementaci\u00f3n\". El presente proyecto tiene el objetivo de fortalecer el proceso de inclusi\u00f3n y participaci\u00f3n de las organizaciones de y para personas con discapacidad, cuidadoras\/es y sus familiares, mediante la entrega de herramientas pr\u00e1cticas a las organizaciones, la promoci\u00f3n de la asociatividad y el posicionamiento de la tem\u00e1tica con los actores relevantes en el territorio de la Macrozona Austral. Para esto propone alcanzar su objetivo general y sus objetivos espec\u00edficos a trav\u00e9s  de aplicaci\u00f3n de m\u00e9todos mixtos multic\u00e9ntricos e intervenciones de base comunitaria, estructurados en cuatro l\u00edneas de trabajo principales, 1) fortalecimiento de las organizaciones en el territorio a partir de la realizaci\u00f3n de un catastro regional y de diagn\u00f3sticos participativos, 2) escuela de gesti\u00f3n social y territorial, 3) actividades de difusi\u00f3n y 4) sistematizaci\u00f3n y evaluaci\u00f3n desde un enfoque de ciencias de la implementaci\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ID: 950106 Resoluci\u00f3n: 5457-2023<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2023 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Servicio Nacional de la Discapacidad (SENADIS)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26690\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26690\" aria-expanded=\"false\" aria-controls=\"collapse-26690\">\n                                            Proyecto de fortalecimiento en capacitaci\u00f3n para el Programa Tr\u00e1nsito a la vida independiente.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26690\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26690\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Capacitar en vida independiente, autonom\u00eda y perspectivas de derechos a equipos profesionales, personas con discapacidad, cuidadoras\/es y servicios de apoyo relacionados al programa Tr\u00e1nsito a la Vida Independiente. La capacitaci\u00f3n se realizar\u00e1 desde un enfoque de derechos, autonom\u00eda, autodeterminaci\u00f3n e independencia, participaci\u00f3n social y vida independiente.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ID: 950106 Resoluci\u00f3n: 5457-2023<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2023 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Servicio Nacional de la Discapacidad (SENADIS)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26842\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26842\" aria-expanded=\"false\" aria-controls=\"collapse-26842\">\n                                            Proyecto de fortalecimiento en capacitaci\u00f3n para el Programa Tr\u00e1nsito a la vida independiente.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26842\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26842\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Capacitar en vida independiente, autonom\u00eda y perspectivas de derechos a equipos profesionales, personas con discapacidad, cuidadoras\/es y servicios de apoyo relacionados al programa Tr\u00e1nsito a la Vida Independiente. La capacitaci\u00f3n se realizar\u00e1 desde un enfoque de derechos, autonom\u00eda, autodeterminaci\u00f3n e independencia, participaci\u00f3n social y vida independiente.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ID: 948796 - Resoluci\u00f3n: 5395-2023<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2023 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Servicio Nacional de la Discapacidad (SENADIS)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26023\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26023\" aria-expanded=\"false\" aria-controls=\"collapse-26023\">\n                                            Transferencia de Innovaci\u00f3n Social para el proceso de Instalaci\u00f3n de Incubadoras de Cooperativas Inclusivas.  \u0093Fortalecimiento de la Red de Incubadoras de Cooperativas Inclusivas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26023\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26023\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Convenio de transferencia para el servicios de asesor\u00eda y acompa\u00f1amiento en la Instalaci\u00f3n de Incubadoras de Cooperativas Inclusivas a Municipalidades adjudicatarias de la Modalidad Continuidad de la Estrategia de Desarrollo Local Inclusivo en las regiones de Atacama, de los R\u00edos, de Magallanes y de la Ant\u00e1rtica Chilena; Valpara\u00edso; Biob\u00edo, Maule y Metropolitana de Santiago. \r\nEl presente proyecto de transferencia de innovaci\u00f3n social, permite entregar soporte t\u00e9cnico y acompa\u00f1ar los procesos de instalaci\u00f3n de Incubadoras de Cooperativas Inclusivas para promover el ejercicio del derecho al trabajo de las personas con discapacidad a trav\u00e9s del desarrollo de un programa de asesor\u00eda, capacitaci\u00f3n y acompa\u00f1amiento que les permita su inserci\u00f3n en el mercado laboral de manera aut\u00f3noma y sustentable. Lo anterior se realiza a trav\u00e9s de un modelo de trabajo integral y transversal, que desarrolle  estrategias flexibles de formaci\u00f3n, asesor\u00eda y acompa\u00f1amiento para promover pertinencia local en la promoci\u00f3n del reconocimiento por parte de actores locales, de espacios de \r\ndesarrollo productivo en el marco de la econom\u00eda social e inclusi\u00f3n de las personas con discapacidad.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ID: 948796 - Resoluci\u00f3n: 5395-2023<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2023 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Servicio Nacional de la Discapacidad (SENADIS)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26688\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26688\" aria-expanded=\"false\" aria-controls=\"collapse-26688\">\n                                            Transferencia de Innovaci\u00f3n Social para el proceso de Instalaci\u00f3n de Incubadoras de Cooperativas Inclusivas.  \u0093Fortalecimiento de la Red de Incubadoras de Cooperativas Inclusivas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26688\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26688\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Convenio de transferencia para el servicios de asesor\u00eda y acompa\u00f1amiento en la Instalaci\u00f3n de Incubadoras de Cooperativas Inclusivas a Municipalidades adjudicatarias de la Modalidad Continuidad de la Estrategia de Desarrollo Local Inclusivo en las regiones de Atacama, de los R\u00edos, de Magallanes y de la Ant\u00e1rtica Chilena; Valpara\u00edso; Biob\u00edo, Maule y Metropolitana de Santiago. \r\nEl presente proyecto de transferencia de innovaci\u00f3n social, permite entregar soporte t\u00e9cnico y acompa\u00f1ar los procesos de instalaci\u00f3n de Incubadoras de Cooperativas Inclusivas para promover el ejercicio del derecho al trabajo de las personas con discapacidad a trav\u00e9s del desarrollo de un programa de asesor\u00eda, capacitaci\u00f3n y acompa\u00f1amiento que les permita su inserci\u00f3n en el mercado laboral de manera aut\u00f3noma y sustentable. Lo anterior se realiza a trav\u00e9s de un modelo de trabajo integral y transversal, que desarrolle  estrategias flexibles de formaci\u00f3n, asesor\u00eda y acompa\u00f1amiento para promover pertinencia local en la promoci\u00f3n del reconocimiento por parte de actores locales, de espacios de \r\ndesarrollo productivo en el marco de la econom\u00eda social e inclusi\u00f3n de las personas con discapacidad.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ID: 948796 - Resoluci\u00f3n: 5395-2023<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2023 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Servicio Nacional de la Discapacidad (SENADIS)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26840\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26840\" aria-expanded=\"false\" aria-controls=\"collapse-26840\">\n                                            Transferencia de Innovaci\u00f3n Social para el proceso de Instalaci\u00f3n de Incubadoras de Cooperativas Inclusivas.  \u0093Fortalecimiento de la Red de Incubadoras de Cooperativas Inclusivas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26840\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26840\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Convenio de transferencia para el servicios de asesor\u00eda y acompa\u00f1amiento en la Instalaci\u00f3n de Incubadoras de Cooperativas Inclusivas a Municipalidades adjudicatarias de la Modalidad Continuidad de la Estrategia de Desarrollo Local Inclusivo en las regiones de Atacama, de los R\u00edos, de Magallanes y de la Ant\u00e1rtica Chilena; Valpara\u00edso; Biob\u00edo, Maule y Metropolitana de Santiago. \r\nEl presente proyecto de transferencia de innovaci\u00f3n social, permite entregar soporte t\u00e9cnico y acompa\u00f1ar los procesos de instalaci\u00f3n de Incubadoras de Cooperativas Inclusivas para promover el ejercicio del derecho al trabajo de las personas con discapacidad a trav\u00e9s del desarrollo de un programa de asesor\u00eda, capacitaci\u00f3n y acompa\u00f1amiento que les permita su inserci\u00f3n en el mercado laboral de manera aut\u00f3noma y sustentable. Lo anterior se realiza a trav\u00e9s de un modelo de trabajo integral y transversal, que desarrolle  estrategias flexibles de formaci\u00f3n, asesor\u00eda y acompa\u00f1amiento para promover pertinencia local en la promoci\u00f3n del reconocimiento por parte de actores locales, de espacios de \r\ndesarrollo productivo en el marco de la econom\u00eda social e inclusi\u00f3n de las personas con discapacidad.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2023 - Marzo 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>INRIA<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26603\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            BIOSEL: BIlevel Optimization in Security, Energy and Logistics\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26603\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26603\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Development of algorithms for bilevel optimization problems with applications in security, electricity and logistics.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> EQM230002<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26267\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortalecimiento de la investigaci\u00f3n y formaci\u00f3n cient\u00edfica en la Universidad de O &#769;Higgins mediante la incorporaci\u00f3n de un espectr\u00f3metro de fluorescencia de rayos X dispersivo de longitudes de onda\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26267\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26267\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Fondequip Mediano EQM230002[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2023 - Noviembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Fundaci\u00f3n para la Innovaci\u00f3n Agraria - FIA<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26351\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Plataforma de asistencia t\u00e9cnica para optimizaci\u00f3n de uso de coberturas para control t\u00e9rmico en el cultivo del cerezo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26351\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26351\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Chile es el tercer pa\u00eds con mayor superficie cultivada de cerezos y principal exportador a nivel mundial. El 82% de la superficie nacional se encuentra concentrada en la zona central, espec\u00edficamente en las regiones del Maule y O\u0092Higgins. Sin embargo, el liderazgo de nuestro pa\u00eds en los mercados internacionales puede estar en \u0093jaque\u0094 por el cambio clim\u00e1tico global. La zona central ha presentado un incremento en la frecuencia de eventos extremos de temperatura m\u00e1xima y olas de calor, que ha afectado a la producci\u00f3n de cerezas durante los \u00faltimos a\u00f1os. Seg\u00fan la proyecci\u00f3n nacional, se espera un incremento en la frecuencia y magnitud de los eventos t\u00e9rmicos extremos y el alza de las temperaturas impacta negativamente la calidad de la fruta y el rendimiento de los huertos de cerezo en 3 periodos cr\u00edticos: desarrollo del fruto, postcosecha y receso invernal. Para enfrentar los embates clim\u00e1ticos se requiere el uso de herramientas tecnol\u00f3gicas que modifiquen el microclima del huerto, siendo una opci\u00f3n las coberturas textiles. El mercado se presenta con una amplia gama de opciones para diferentes momentos del proceso productivo, lo que ha generado efectos adversos debido al desconocimiento del manejo de las coberturas por los productores y ha impedido mejorar su competitividad. Por ello nuestra propuesta de valor busca validar el uso de las coberturas textiles en periodos poco explorados del ciclo productivo del huerto de cerezo y optimizar el uso de coberturas invernales y mallas fotoselectivas como herramienta tecnol\u00f3gica de control t\u00e9rmico. Se determinar\u00e1 la eficiencia de estas coberturas en los diferentes periodos cr\u00edticos del ciclo productivo de huertos de cerezo en la zona central, junto con la estimaci\u00f3n de \u00edndices de eficiencia de manejo por tipo de cobertura y condici\u00f3n clim\u00e1tica. Con la informaci\u00f3n obtenida, se crear\u00e1 una plataforma virtual de asistencia t\u00e9cnica amigable para productores que los gu\u00ede en el uso eficiente de coberturas para control t\u00e9rmico.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2023 - Diciembre 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26352\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Towards a sustainable fruit production: deciphering the effect of rootstock x scion interaction on the adaptability of stone fruit trees (Prunus spp.) to climate change,\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26352\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26352\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Resumen ejecutivo\r\n \r\nConcurso: Fortalecimiento Centros Regionales ANID\r\n\r\nInstituci\u00f3n Principal: Centro de Estudios Avanzados en Fruticultura \u0096 CEAF\r\n\r\nTowards a sustainable fruit production: deciphering the effect of rootstock x scion interaction on the adaptability of stone fruit trees (Prunus spp.) to climate change.\r\n\r\nEsta propuesta se enfoca en el estudio de los efectos de los nuevos genotipos h\u00edbridos generados por el Programa de Mejoramiento Gen\u00e9tico de portainjertos de Prunus spp. CEAF sobre la adaptaci\u00f3n a estr\u00e9s h\u00eddrico y t\u00e9rmico de cultivares de frutales de carozo tanto a nivel de plantas injertadas j\u00f3venes y adultas en etapa productiva.\r\n\r\nUna parte de esta propuesta se centra en validar marcadores de selecci\u00f3n temprana sobre plantas injertadas identificados en genotipos de portainjertos de Prunus spp. contrastantes en su respuesta a estr\u00e9s h\u00eddrico. Adem\u00e1s, a nivel de huerto experimental, se determinar\u00e1 el efecto de los portainjertos h\u00edbridos sobre la biolog\u00eda reproductiva y productividad de variedades de frutales de carozo expuestos a estr\u00e9s h\u00eddrico y t\u00e9rmico.\r\n\r\nLos estudios ser\u00e1n conducidos por las L\u00edneas de Fisiolog\u00eda del Estr\u00e9s, Gen\u00f3mica Vegetal y Mejoramiento Gen\u00e9tico del CEAF, con la colaboraci\u00f3n de investigadores asociados pertinentes a los objetivos de investigaci\u00f3n y la formaci\u00f3n de capital humano estudiantes de pregrado y programas de posgrado financiados por la propuesta. \r\n\r\nSe plantea como hip\u00f3tesis que \u0093los nuevos portainjertos h\u00edbridos de Prunus modulan los mecanismos moleculares, fisiol\u00f3gicos y reproductivos, determinando la tolerancia de la unidad portainjerto x variedad frente al d\u00e9ficit h\u00eddrico y estr\u00e9s cal\u00f3rico\u0094.\r\n     \r\nEn el marco de este proyecto se plantean los siguientes objetivos investigaci\u00f3n: \r\n1.\tAnalizar las posibles asociaciones entre la diversidad al\u00e9lica de los genes candidatos y la variabilidad de la tolerancia al d\u00e9ficit h\u00eddrico en plantas injertadas.\r\n2.\tValidar marcadores fisiol\u00f3gicos y metab\u00f3licos en combinaci\u00f3n injerto\/cultivar sometidos a d\u00e9ficit h\u00eddrico.\r\n3.\tIdentificar y validar la respuesta hormonal e hidr\u00e1ulica de la planta en la interacci\u00f3n entre los nuevos h\u00edbridos de portainjertos y cultivares de Prunus frente al d\u00e9ficit h\u00eddrico.\r\n4.\tEvaluar el efecto de la interacci\u00f3n portainjerto x cultivar sobre la organog\u00e9nesis floral y la calidad del fruto en \u00e1rboles adultos bajo d\u00e9ficit h\u00eddrico y estr\u00e9s t\u00e9rmico.\r\n5.\tDesarrollar actividades difusi\u00f3n y divulgaci\u00f3n de resultados del proyecto que den cuenta del trabajo conjunto de las Instituciones involucradas y los hallazgos logrados por la presente propuesta de investigaci\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 23PDT-248765<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2023 - Noviembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Corporaci\u00f3n de Fomento de la Producci\u00f3n - CORFO<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26353\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Paquete tecnol\u00f3gico para mejorar la calidad de la fruta de la ciruela japonesa \u0093Sweet Pekeetah\u0094 ante el actual escenario de cambio clim\u00e1tico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26353\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26353\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto busca transferir un paquete tecnol\u00f3gico a las empresas\r\nagr\u00edcolas que producen la nueva variedad de ciruela japonesa \u0093Sweet Pekeetah\u0094, a trav\u00e9s de\r\nmejores tecnolog\u00edas y t\u00e9cnicas de manejo de los huertos, ante un escenario de incremento de las\r\ntemperaturas durante el per\u00edodo crecimiento y maduraci\u00f3n de la fruta, para asegurar una\r\nexcelente calidad organol\u00e9ptica, mejorando as\u00ed la competitividad de las empresas beneficiarias.\r\nLas brechas de productividad identificadas, que se busca atender con el proyecto, tienen relaci\u00f3n\r\ncon una falta de zonificaci\u00f3n agroclim\u00e1tica de los huertos que permita identificar la incidencia de\r\naltas temperaturas estivales, falta de herramientas y manejos para evitar una maduraci\u00f3n y\r\nablandamiento acelerado de la fruta y concentraci\u00f3n de s\u00f3lidos solubles bajo el \u00f3ptimo, que\r\ndisminuye la calidad organol\u00e9ptica de la fruta.\r\nLa soluci\u00f3n propuesta busca difundir y adoptar un paquete tecnol\u00f3gico que intervenga, con\r\nmanejos agron\u00f3micos adecuados, los puntos cr\u00edticos de la producci\u00f3n y que han mostrado ser\r\nefectivos en mejorar la calidad organol\u00e9ptica de la fruta. Por una parte, se caracterizar\u00e1 y\r\nzonificar\u00e1 el ambiente agroclim\u00e1tico donde est\u00e1n emplazados los huertos de los beneficiarios, de\r\nacuerdo al nivel de ocurrencia de eventos de estr\u00e9s t\u00e9rmico, se definir\u00e1n determinantes\r\nfisiol\u00f3gicas que regulan la maduraci\u00f3n de la fruta, abordando tem\u00e1ticas relacionadas al manejo de\r\ncarga, estrategias de fertilizaci\u00f3n y uso de reguladores de crecimiento.\r\nEl paquete tecnol\u00f3gico ser\u00e1 transferido a las empresas atendidas a trav\u00e9s de unidades\r\ndemostrativas, d\u00edas de campo, jornadas t\u00e9cnicas de transferencia y seminarios. Las empresas que\r\nser\u00e1n atendidas corresponden a empresas agr\u00edcolas dedicadas a la producci\u00f3n de fruta fresca de\r\nexportaci\u00f3n y que tienen establecidos huertos comerciales de \u0091Sweet Pekeetah\u0092, a empresas\r\nexportadoras de fruta fresca, que en la actualidad comercializan la variedad y viveros de plantas\r\nfrutales que propagan plantas de la variedad.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> EQM230041<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2023 - Noviembre 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26475\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Control distribuido de sistemas de conversi\u00f3n emergentes para una red el\u00e9ctrica m\u00e1s resiliente\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26475\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26475\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Plataforma experimental de control distribuido de m\u00f3dulos de potencia\r\nConsiste en diversos m\u00f3dulos de baja potencia que pueden configurarse e interconectarse para implementar variadas topolog\u00edas emergentes de sistemas el\u00e9ctricos y topolog\u00edas de conversi\u00f3n como: microrredes, enlaces de alto voltaje en corriente continua (HVDC), convertidores modulares multinivel (MMC), sistemas de bater\u00edas (BESS), cargadores r\u00e1pidos, entre otros. Cada m\u00f3dulo de potencia posee una unidad de control propia coordinada por una unidad central, lo que permite implementar esquemas de control distribuido. Adem\u00e1s, la plataforma contempla una etapa de amplificaci\u00f3n de potencia trif\u00e1sica, que permite generar f\u00edsicamente los voltajes y corrientes de un punto com\u00fan de acoplamiento con una red el\u00e9ctrica emulada en tiempo-real. Esto permite estudiar la interacci\u00f3n de la red emulada con los sistemas el\u00e9ctricos y las topolog\u00edas de conversi\u00f3n emergentes descritas anteriormente. Por consiguiente, esta plataforma agiliza el prototipado, tanto en hardware de potencia como de control, permitiendo la validaci\u00f3n experimental de estrategias de control distribuido que, a diferencia del control centralizado (tradicionalmente utilizado en la academia e industria), presenta ventajas que son de utilidad para mejorar la resiliencia de los sistemas el\u00e9ctricos, como son: mejor confiabilidad, flexibilidad, escalabilidad, operaci\u00f3n plug-and-play y tolerancia a fallas de un solo punto.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> EQM230041<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2023 - Noviembre 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26596\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Control distribuido de sistemas de conversi\u00f3n emergentes para una red el\u00e9ctrica m\u00e1s resiliente\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26596\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26596\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Plataforma experimental de control distribuido de m\u00f3dulos de potencia\r\nConsiste en diversos m\u00f3dulos de baja potencia que pueden configurarse e interconectarse para implementar variadas topolog\u00edas emergentes de sistemas el\u00e9ctricos y topolog\u00edas de conversi\u00f3n como: microrredes, enlaces de alto voltaje en corriente continua (HVDC), convertidores modulares multinivel (MMC), sistemas de bater\u00edas (BESS), cargadores r\u00e1pidos, entre otros. Cada m\u00f3dulo de potencia posee una unidad de control propia coordinada por una unidad central, lo que permite implementar esquemas de control distribuido. Adem\u00e1s, la plataforma contempla una etapa de amplificaci\u00f3n de potencia trif\u00e1sica, que permite generar f\u00edsicamente los voltajes y corrientes de un punto com\u00fan de acoplamiento con una red el\u00e9ctrica emulada en tiempo-real. Esto permite estudiar la interacci\u00f3n de la red emulada con los sistemas el\u00e9ctricos y las topolog\u00edas de conversi\u00f3n emergentes descritas anteriormente. Por consiguiente, esta plataforma agiliza el prototipado, tanto en hardware de potencia como de control, permitiendo la validaci\u00f3n experimental de estrategias de control distribuido que, a diferencia del control centralizado (tradicionalmente utilizado en la academia e industria), presenta ventajas que son de utilidad para mejorar la resiliencia de los sistemas el\u00e9ctricos, como son: mejor confiabilidad, flexibilidad, escalabilidad, operaci\u00f3n plug-and-play y tolerancia a fallas de un solo punto.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> EQM230002<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26619\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortalecimiento de la investigaci\u00f3n y formaci\u00f3n cient\u00edfica en la Universidad de O &#769;Higgins mediante la incorporaci\u00f3n de un espectr\u00f3metro de fluorescencia de rayos X dispersivo de longitudes de onda\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26619\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26619\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Fondequip Mediano EQM230002[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2023 - Noviembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Fundaci\u00f3n para la Innovaci\u00f3n Agraria - FIA<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26642\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Plataforma de asistencia t\u00e9cnica para optimizaci\u00f3n de uso de coberturas para control t\u00e9rmico en el cultivo del cerezo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26642\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26642\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Chile es el tercer pa\u00eds con mayor superficie cultivada de cerezos y principal exportador a nivel mundial. El 82% de la superficie nacional se encuentra concentrada en la zona central, espec\u00edficamente en las regiones del Maule y O\u0092Higgins. Sin embargo, el liderazgo de nuestro pa\u00eds en los mercados internacionales puede estar en \u0093jaque\u0094 por el cambio clim\u00e1tico global. La zona central ha presentado un incremento en la frecuencia de eventos extremos de temperatura m\u00e1xima y olas de calor, que ha afectado a la producci\u00f3n de cerezas durante los \u00faltimos a\u00f1os. Seg\u00fan la proyecci\u00f3n nacional, se espera un incremento en la frecuencia y magnitud de los eventos t\u00e9rmicos extremos y el alza de las temperaturas impacta negativamente la calidad de la fruta y el rendimiento de los huertos de cerezo en 3 periodos cr\u00edticos: desarrollo del fruto, postcosecha y receso invernal. Para enfrentar los embates clim\u00e1ticos se requiere el uso de herramientas tecnol\u00f3gicas que modifiquen el microclima del huerto, siendo una opci\u00f3n las coberturas textiles. El mercado se presenta con una amplia gama de opciones para diferentes momentos del proceso productivo, lo que ha generado efectos adversos debido al desconocimiento del manejo de las coberturas por los productores y ha impedido mejorar su competitividad. Por ello nuestra propuesta de valor busca validar el uso de las coberturas textiles en periodos poco explorados del ciclo productivo del huerto de cerezo y optimizar el uso de coberturas invernales y mallas fotoselectivas como herramienta tecnol\u00f3gica de control t\u00e9rmico. Se determinar\u00e1 la eficiencia de estas coberturas en los diferentes periodos cr\u00edticos del ciclo productivo de huertos de cerezo en la zona central, junto con la estimaci\u00f3n de \u00edndices de eficiencia de manejo por tipo de cobertura y condici\u00f3n clim\u00e1tica. Con la informaci\u00f3n obtenida, se crear\u00e1 una plataforma virtual de asistencia t\u00e9cnica amigable para productores que los gu\u00ede en el uso eficiente de coberturas para control t\u00e9rmico.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> EQM230041<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2023 - Noviembre 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26881\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Control distribuido de sistemas de conversi\u00f3n emergentes para una red el\u00e9ctrica m\u00e1s resiliente\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26881\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26881\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Plataforma experimental de control distribuido de m\u00f3dulos de potencia\r\nConsiste en diversos m\u00f3dulos de baja potencia que pueden configurarse e interconectarse para implementar variadas topolog\u00edas emergentes de sistemas el\u00e9ctricos y topolog\u00edas de conversi\u00f3n como: microrredes, enlaces de alto voltaje en corriente continua (HVDC), convertidores modulares multinivel (MMC), sistemas de bater\u00edas (BESS), cargadores r\u00e1pidos, entre otros. Cada m\u00f3dulo de potencia posee una unidad de control propia coordinada por una unidad central, lo que permite implementar esquemas de control distribuido. Adem\u00e1s, la plataforma contempla una etapa de amplificaci\u00f3n de potencia trif\u00e1sica, que permite generar f\u00edsicamente los voltajes y corrientes de un punto com\u00fan de acoplamiento con una red el\u00e9ctrica emulada en tiempo-real. Esto permite estudiar la interacci\u00f3n de la red emulada con los sistemas el\u00e9ctricos y las topolog\u00edas de conversi\u00f3n emergentes descritas anteriormente. Por consiguiente, esta plataforma agiliza el prototipado, tanto en hardware de potencia como de control, permitiendo la validaci\u00f3n experimental de estrategias de control distribuido que, a diferencia del control centralizado (tradicionalmente utilizado en la academia e industria), presenta ventajas que son de utilidad para mejorar la resiliencia de los sistemas el\u00e9ctricos, como son: mejor confiabilidad, flexibilidad, escalabilidad, operaci\u00f3n plug-and-play y tolerancia a fallas de un solo punto.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> EQM230002<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26997\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortalecimiento de la investigaci\u00f3n y formaci\u00f3n cient\u00edfica en la Universidad de O &#769;Higgins mediante la incorporaci\u00f3n de un espectr\u00f3metro de fluorescencia de rayos X dispersivo de longitudes de onda\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26997\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26997\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Fondequip Mediano EQM230002[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> EQM230002<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27049\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortalecimiento de la investigaci\u00f3n y formaci\u00f3n cient\u00edfica en la Universidad de O &#769;Higgins mediante la incorporaci\u00f3n de un espectr\u00f3metro de fluorescencia de rayos X dispersivo de longitudes de onda\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27049\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27049\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Fondequip Mediano EQM230002[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26592\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Configurable Electrical Vehicle Supply Equipment for Testing Electric Vehicles and Enhancing Interoperability with Smart Grids\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26592\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26592\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Un tercio del consumo energ\u00e9tico final en Chile corresponde al sector del transporte, lo que representa aproximadamente el 20% de las emisiones totales de gases de efecto invernadero (GEI) del pa\u00eds. Los veh\u00edculos el\u00e9ctricos presentan una interesante oportunidad pues contribuyen a reducir las emisiones de GEI al obtener su energ\u00eda de fuentes limpias. Actualmente la participaci\u00f3n de Chile en el mercado automotriz, especialmente en veh\u00edculos el\u00e9ctricos, es baja, por lo que se han generado pol\u00edticas p\u00fablicas para fomentar el desarrollo de la electromovilidad. Se espera que para el a\u00f1o 2035, el 100% de los veh\u00edculos privados y el 100% de la flota de transporte p\u00fablico sean el\u00e9ctricos. Esto plantea numerosos desaf\u00edos, especialmente en t\u00e9rminos de infraestructura de carga, donde se estima que se necesitar\u00e1n m\u00e1s de 130,000 puntos de carga para el a\u00f1o 2035.  \r\n\r\nEn este contexto, este proyecto busca implementar una plataforma llamada \"Configurable Electrical Vehicle Supply Equipment for Testing Electric Vehicles and Enhancing Interoperability with Smart Grids\", que consta de 4 unidades capaces de realizar pruebas de operaci\u00f3n multiprotocolo y an\u00e1lisis de comunicaciones para evaluar interoperabilidad, protocolos, est\u00e1ndares de carga y aplicaciones de vehicle-to-grid y vehicle-to-vehicle. Cada unidad, llamada Charging Discovery System, puede emular veh\u00edculos el\u00e9ctricos y cargadores, utilizando fuentes programables que no solo emulan los protocolos, sino que tambi\u00e9n generan transferencia de energ\u00eda el\u00e9ctrica, simulando el proceso de carga en tiempo real. Adem\u00e1s, se complementar\u00e1 la plataforma con un veh\u00edculo el\u00e9ctrico equipado con los protocolos de comunicaci\u00f3n CCS2 y GBT, considerando el est\u00e1ndar chino de comunicaciones.  \r\n\r\nEl equipo de investigaci\u00f3n, liderado por la Universidad de Santiago de Chile, cuenta con la colaboraci\u00f3n de la Universidad Andr\u00e9s Bello, Universidad de O'Higgins y Universidad Austral de Chile, donde se instalar\u00e1n las unidades de la plataforma. Asimismo, se cuenta con colaboraciones internacionales de la Universidad de Nottingham, Zurich U. of Applied Sciences y la Universidad de Costa Rica. El proyecto cuenta con el patrocinio del Ministerio de Energ\u00eda del Gobierno de Chile y la Agencia de Sostenibilidad Energ\u00e9tica, instituciones encargadas de promover pol\u00edticas y desarrollar la electromovilidad a nivel nacional. Tambi\u00e9n se ha establecido una colaboraci\u00f3n con 4 liceos con el objetivo de difundir temas relacionados con la electromovilidad entre los estudiantes secundarios, quienes podr\u00e1n visitar y utilizar el equipo en actividades de divulgaci\u00f3n. \r\n\r\nEl equipo investigador cuenta con una s\u00f3lida experiencia demostrada a trav\u00e9s de proyectos en curso y publicaciones en el campo de estudio, destacando una amplia red de colaboraci\u00f3n. La implementaci\u00f3n de esta plataforma ser\u00e1 una valiosa contribuci\u00f3n para estudiantes y acad\u00e9micos asociados a 13 programas de pregrado y posgrado en universidades nacionales, as\u00ed como a 9 programas acad\u00e9micos internacionales y hasta 8 proyectos de investigaci\u00f3n vigentes hasta el 2025. \r\n \r\nLa instalaci\u00f3n de esta plataforma permitir\u00e1 generar publicaciones indexadas de alta calidad, ofrecer tesis de pregrado y posgrado, establecer redes de contacto, organizar eventos de divulgaci\u00f3n y brindar servicios de asesor\u00eda t\u00e9cnica a la industria.  \r\n\r\nDe esta manera, se contribuir\u00e1 a dotar al pa\u00eds instalaciones \u00fanicas a nivel regional, fortaleciendo la capacidad de generar investigaci\u00f3n y desarrollo en electromovilidad.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FONDEQUIP EQM230041<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2023 - Diciembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26466\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Control distribuido de sistemas de conversi\u00f3n emergentes para una red el\u00e9ctrica m\u00e1s resiliente\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26466\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26466\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Consiste en diversos m\u00f3dulos de baja potencia que pueden configurarse e\r\ninterconectarse para implementar variadas topolog\u00edas emergentes de\r\nsistemas el\u00e9ctricos y topolog\u00edas de conversi\u00f3n como: microrredes, enlaces\r\nde alto voltaje en corriente continua (HVDC), convertidores modulares\r\nmultinivel (MMC), sistemas de bater\u00edas (BESS), cargadores r\u00e1pidos, entre\r\notros. Cada m\u00f3dulo de potencia posee una unidad de control propia\r\ncoordinada por una unidad central, lo que permite implementar esquemas\r\nde control distribuido. Adem\u00e1s, la plataforma contempla una etapa de\r\namplificaci\u00f3n de potencia trif\u00e1sica, que permite generar f\u00edsicamente los\r\nvoltajes y corrientes de un punto com\u00fan de acoplamiento con una red\r\nel\u00e9ctrica emulada en tiempo-real. Esto permite estudiar la interacci\u00f3n de la\r\nred emulada con los sistemas el\u00e9ctricos y las topolog\u00edas de conversi\u00f3n\r\nemergentes descritas anteriormente. Por consiguiente, esta plataforma\r\nagiliza el prototipado, tanto en hardware de potencia como de control,\r\npermitiendo la validaci\u00f3n experimental de estrategias de control\r\ndistribuido que, a diferencia del control centralizado (tradicionalmente\r\nutilizado en la academia e industria), presenta ventajas que son de utilidad\r\npara mejorar la resiliencia de los sistemas el\u00e9ctricos, como son: mejor\r\nconfiabilidad, flexibilidad, escalabilidad, operaci\u00f3n plug-and-play y\r\ntolerancia a fallas de un solo punto.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FONDEQUIP EQM230041<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2023 - Diciembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26589\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Control distribuido de sistemas de conversi\u00f3n emergentes para una red el\u00e9ctrica m\u00e1s resiliente\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26589\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26589\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Consiste en diversos m\u00f3dulos de baja potencia que pueden configurarse e\r\ninterconectarse para implementar variadas topolog\u00edas emergentes de\r\nsistemas el\u00e9ctricos y topolog\u00edas de conversi\u00f3n como: microrredes, enlaces\r\nde alto voltaje en corriente continua (HVDC), convertidores modulares\r\nmultinivel (MMC), sistemas de bater\u00edas (BESS), cargadores r\u00e1pidos, entre\r\notros. Cada m\u00f3dulo de potencia posee una unidad de control propia\r\ncoordinada por una unidad central, lo que permite implementar esquemas\r\nde control distribuido. Adem\u00e1s, la plataforma contempla una etapa de\r\namplificaci\u00f3n de potencia trif\u00e1sica, que permite generar f\u00edsicamente los\r\nvoltajes y corrientes de un punto com\u00fan de acoplamiento con una red\r\nel\u00e9ctrica emulada en tiempo-real. Esto permite estudiar la interacci\u00f3n de la\r\nred emulada con los sistemas el\u00e9ctricos y las topolog\u00edas de conversi\u00f3n\r\nemergentes descritas anteriormente. Por consiguiente, esta plataforma\r\nagiliza el prototipado, tanto en hardware de potencia como de control,\r\npermitiendo la validaci\u00f3n experimental de estrategias de control\r\ndistribuido que, a diferencia del control centralizado (tradicionalmente\r\nutilizado en la academia e industria), presenta ventajas que son de utilidad\r\npara mejorar la resiliencia de los sistemas el\u00e9ctricos, como son: mejor\r\nconfiabilidad, flexibilidad, escalabilidad, operaci\u00f3n plug-and-play y\r\ntolerancia a fallas de un solo punto.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FONDEQUIP EQM230041<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2023 - Diciembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26598\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Control distribuido de sistemas de conversi\u00f3n emergentes para una red el\u00e9ctrica m\u00e1s resiliente\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26598\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26598\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Consiste en diversos m\u00f3dulos de baja potencia que pueden configurarse e\r\ninterconectarse para implementar variadas topolog\u00edas emergentes de\r\nsistemas el\u00e9ctricos y topolog\u00edas de conversi\u00f3n como: microrredes, enlaces\r\nde alto voltaje en corriente continua (HVDC), convertidores modulares\r\nmultinivel (MMC), sistemas de bater\u00edas (BESS), cargadores r\u00e1pidos, entre\r\notros. Cada m\u00f3dulo de potencia posee una unidad de control propia\r\ncoordinada por una unidad central, lo que permite implementar esquemas\r\nde control distribuido. Adem\u00e1s, la plataforma contempla una etapa de\r\namplificaci\u00f3n de potencia trif\u00e1sica, que permite generar f\u00edsicamente los\r\nvoltajes y corrientes de un punto com\u00fan de acoplamiento con una red\r\nel\u00e9ctrica emulada en tiempo-real. Esto permite estudiar la interacci\u00f3n de la\r\nred emulada con los sistemas el\u00e9ctricos y las topolog\u00edas de conversi\u00f3n\r\nemergentes descritas anteriormente. Por consiguiente, esta plataforma\r\nagiliza el prototipado, tanto en hardware de potencia como de control,\r\npermitiendo la validaci\u00f3n experimental de estrategias de control\r\ndistribuido que, a diferencia del control centralizado (tradicionalmente\r\nutilizado en la academia e industria), presenta ventajas que son de utilidad\r\npara mejorar la resiliencia de los sistemas el\u00e9ctricos, como son: mejor\r\nconfiabilidad, flexibilidad, escalabilidad, operaci\u00f3n plug-and-play y\r\ntolerancia a fallas de un solo punto.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> CP23-P028<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2023 - Noviembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Ciencia, Tecnolog\u00eda, Conocimiento e Innovaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26859\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Itinerancia Audiovisual Interactivo \u0093Agua y Territorio\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26859\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26859\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El producto Audiovisual Interactivo \u0093Agua y Territorio\u0094 es un audiovisual generado con Realidad Aumentada, que puede ser utilizado en soporte oculus o directamente desde la web. En este audiovisual se presenta una maqueta de cuenca hidrogr\u00e1fica, donde el p\u00fablico podr\u00e1 apropiarse de conocimiento cient\u00edfico asociado al ciclo del agua e interactuar con im\u00e1genes en el caso de la realidad aumentada. El contenido cuenta con una experiencia integrativa con la hidrolog\u00eda, abarcando los estados del agua, sus procesos f\u00edsicos y recorridos desde la cordillera hasta su desembocadura con descripci\u00f3n auditiva del viento, precipitaci\u00f3n, escorrent\u00eda, r\u00edos y del agua. Esta experiencia se divide en 6 etapas; Estado Del Agua Cuenca General \/ El Agua y la Cuenca Alta \/ El Agua y la Cuenca Media \/El Agua y la Cuenca Baja \/ Cuenca y Agua del Ser Humano \/ Tipos de Nubes.\r\nLa itinerancia de este producto se fundamenta en la importancia de tener conocimiento sobre los estados del agua y sus procesos, siendo la base para apropiar otros conceptos y pr\u00e1cticas que permitir\u00e1n desarrollar acciones de mitigaci\u00f3n contra la sequ\u00eda y la desertificaci\u00f3n. Como objetivo general se busca concientizar al p\u00fablico sobre los conceptos b\u00e1sicos del agua y sus usos, permitiendo levantar una alerta sobre la convivencia de la actividad humana y econ\u00f3mica. \r\nEl producto est\u00e1 dirigido a un p\u00fablico de  7 a 18 a\u00f1os y sus familias, adem\u00e1s de adultos interesadas\/os.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ensayo clinico<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26332\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Riesgo cardiovascular en una cohorte de sobrevivientes de c\u00e1ncer infantil en Chile: estudio piloto que eval\u00faa el impacto del entrenamiento f\u00edsico en marcadores de capacidad cardiorrespiratoria y ocurrencia de cardiotoxicidad\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26332\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26332\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Antecedentes: los sobrevivientes de c\u00e1ncer son una poblaci\u00f3n en r\u00e1pido crecimiento con necesidades de salud espec\u00edficas. En los EE. UU., aproximadamente 17 millones de adultos son sobrevivientes de c\u00e1ncer, lo que representa el 5 % de la poblaci\u00f3n adulta, y las proyecciones indican que este n\u00famero aumentar\u00e1 a 20 millones para 2026, seg\u00fan el  Instituto Nacional del C\u00e1ncer de Estados Unidos. Los eventos cardiovasculares son la principal causa (no maligna) de muerte entre los sobrevivientes de c\u00e1ncer, con un riesgo de muerte aproximadamente siete veces mayor en relaci\u00f3n con sus contrapartes de la misma edad. Por tanto, el estudio de los factores de riesgo CV en pacientes oncol\u00f3gicos pedi\u00e1tricos supervivientes es un tema en auge, con ensayos cl\u00ednicos prospectivos en marcha y que actualmente carecen de una base mecan\u00edstica. Cada a\u00f1o en Chile se presentan aproximadamente 400 casos nuevos de c\u00e1ncer infantil, y sabiendo que la sobrevida global es cercana al 60%, llegamos a un n\u00famero apreciable de ni\u00f1os (alrededor de 240) que logran superar su enfermedad a\u00f1o tras a\u00f1o. Sin embargo, desde el inicio del programa, la monitorizaci\u00f3n del riesgo CV ha sido insuficiente, a pesar de que el 60-70% de los protocolos del PINDA (Programa Infantil para Drogas Antineopl\u00e1sicas) incluyen antraciclinas, que son agentes quimioter\u00e1picos relacionados con alto riesgo de cardiotoxicidad. En relaci\u00f3n a las medidas de intervenci\u00f3n disiponibles, es bien sabido que el entrenamiento aer\u00f3bico conduce a una mayor capacidad\/aptitud cardiorrespiratoria, CCR (ingl\u00e9s CRF; cardiorrespiratoty fitness). Por otro lado, el tipo de entrenamiento, en el caso de resistencia aumenta significativamente la fuerza muscular y mejora la forma f\u00edsica, asoci\u00e1ndose a mejor\u00eda de los outcomes cardiovasculares en adultos sobreviviente de c\u00e1ncer. En esta poblaci\u00f3n se ha visto que un CCR m\u00e1s baja se asocia con una mayor carga de s\u00edntomas y un mayor riesgo de morbilidad y mortalidad CV por afecciones no cancerosas; sin embargo, la relaci\u00f3n entre la aptitud f\u00edsica expresada por la CCR y la ocurrencia de cardiotoxicidad no ha sido bien caracterizadas en la poblaci\u00f3n infantil, o en la transici\u00f3n infantil-adulto, ya que cuentan con un vac\u00edo de seguimiento CV. Con base en estos antecedentes, planteamos la hip\u00f3tesis de que mejorar la condici\u00f3n\/aptitud f\u00edsica en una cohorte de sobrevivientes de c\u00e1ncer infantil a trav\u00e9s de la intervenci\u00f3n con ejercicios se asocia con una disminuci\u00f3n de los factores de riesgo cardiovascular y los marcadores ocurrencia de cardiotoxicidad.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2023 - Abril 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Secretaria Regional Ministerial de las Culturas, las Artes y el Patrimonio de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26079\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estudio de Caracterizaci\u00f3n de las Artesan\u00edas, Artes y Oficios de la Regi\u00f3n del Libertador Bernardo O\u0092Higgins &#8211; Etapa I\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26079\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26079\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Estudio de l\u00ednea base regional cuyo prop\u00f3sito es levantar datos mixtos sobre los \u00e1mbitos del arte, artesan\u00edas y oficios para aportar a la implementaci\u00f3n de la Escuela Regional de Artes, Artesan\u00edas y Oficios de O'Higgins. Entre sus objetivos se incluye caracterizar la labor de los\/las artesanos\/as, artistas visuales y exponentes de oficios\r\ntradicionales de la regi\u00f3n, en t\u00e9rminos de su ubicaci\u00f3n geogr\u00e1fica, los procesos de aprendizaje de su t\u00e9cnica, transferencia de conocimientos, difusi\u00f3n y valoraci\u00f3n material e inmaterial de sus obras.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> it23i0003<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2023 - Octubre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26211\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estandarizaci\u00f3n de ITeRDEA: Instrumento informatizado para la Identificaci\u00f3n Temprana y el Seguimiento del Riesgo de presentar Dificultades Espec\u00edficas del Aprendizaje, a partir de predictores cognitivos, en escolares de primero a sexto b\u00e1sico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26211\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26211\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El problema que se aborda en este proyecto es la identificaci\u00f3n temprana y el seguimiento de la trayectoria de desarrollo cognitivo de escolares de primero a sexto b\u00e1sico en riesgo de presentar Dificultades Espec\u00edficas en el Aprendizaje (DEA). Actualmente en Chile no existe una estrategia implementada para el tamizaje universal del riesgo de DEA, por lo que un escolar es evaluado cuando ya presenta dificultades en su rendimiento acad\u00e9mico. En otras palabras, se realiza el diagn\u00f3stico una vez que se ha instaurado el trastorno. Este diagn\u00f3stico se realiza habitualmente con pruebas psicopedag\u00f3gicas curriculares que eval\u00faan la dificultad acad\u00e9mica del ni\u00f1o, pero no realmente la causa que la origina, dificultando la selecci\u00f3n de una intervenci\u00f3n precisa dirigida a este origen. Atendiendo a lo anterior, en este proyecto se ofrece como soluci\u00f3n realizar la estandarizaci\u00f3n a nivel nacional de la versi\u00f3n final de ITeRDEA: un instrumento informatizado para la identificaci\u00f3n temprana y el seguimiento del riesgo de presentar DEA en matem\u00e1ticas, lectura y escritura, a partir de predictores cognitivos, en escolares de primero a sexto b\u00e1sico, cuyo prototipo fue construido y validado a peque\u00f1a escala en un proyecto previo (FONDEF ID18I10002). ITeRDEA quedar\u00e1 conformado por tres bater\u00edas de evaluaci\u00f3n de predictores cognitivos: Bater\u00eda de Predictores de Matem\u00e1ticas, Bater\u00eda de Predictores de Lectura\/Escritura y Bater\u00eda de Funciones Ejecutivas. Luego de que el escolar sea evaluado, el instrumento generar\u00e1, a partir de normas tipificadas, un reporte autom\u00e1tico donde se ofrecer\u00e1 el perfil cognitivo del ni\u00f1o\/a en cada capacidad cognitiva b\u00e1sica (CCB) evaluada y una caracterizaci\u00f3n general de este perfil, indicando la posibilidad de riesgo de DEA o de bajo rendimiento acad\u00e9mico con conservaci\u00f3n de las CCB. La hip\u00f3tesis general propone que ITeRDEA permitir\u00e1 realizar, a nivel nacional, la identificaci\u00f3n del riesgo de presentar DEA en matem\u00e1ticas, lectura y\/o escritura en escolares de primero a sexto b\u00e1sico, a trav\u00e9s de la evaluaci\u00f3n de predictores cognitivos del posterior rendimiento acad\u00e9mico. En consecuencia, el objetivo general del proyecto consiste en estandarizar la versi\u00f3n final del instrumento ITeRDEA. El principal componente de investigaci\u00f3n del proyecto tiene relaci\u00f3n con poner a prueba en una situaci\u00f3n real (no experimental) y de relevancia social los supuestos de las teor\u00edas cognitivas que proponen a las CCB como predictores de los posteriores aprendizajes acad\u00e9micos. Para ello, se han utilizado dichos supuestos para el dise\u00f1o y validaci\u00f3n de un instrumento de tamizaje universal que permitir\u00e1 la identificaci\u00f3n temprana de riesgo de dificultades en el aprendizaje. Con la implementaci\u00f3n de ITeRDEA en las escuelas p\u00fablicas de nuestro pa\u00eds, la investigaci\u00f3n cient\u00edfica se pone al servicio de las buenas pr\u00e1cticas educativas en la identificaci\u00f3n temprana de necesidades educativas especiales, particularmente de las DEA. Como resultado de producci\u00f3n del proyecto se considera la entrega de ITeRDEA estandarizado a nivel nacional, y siendo este un proyecto de inter\u00e9s p\u00fablico, se trabajar\u00e1 en estrecha colaboraci\u00f3n con el Mandante, el Ministerio de Educaci\u00f3n, v\u00eda su Divisi\u00f3n de Educaci\u00f3n General, para la estandarizaci\u00f3n y masificaci\u00f3n del instrumento a las escuelas del pa\u00eds. Los beneficiarios principales de ITeRDEA ser\u00e1n los ni\u00f1o\/as evaluados, pero adicionalmente se benefician las escuelas y, en general, la Educaci\u00f3n P\u00fablica nacional.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26265\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            BioSav. Centro UOH de Biolog\u00eda de Sistemas para la Sanidad Vegetal.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26265\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26265\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Apoyo a la creaci\u00f3n de centros de investigaci\u00f3n UOH 2023.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26394\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            BioSav. Centro UOH de Biolog\u00eda de Sistemas para la Sanidad Vegetal.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26394\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26394\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Apoyo a la creaci\u00f3n de centros de investigaci\u00f3n UOH 2023.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>UK Research and Innovation<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26487\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Quantifying the 2022-2023 altitudinal range-wide tree mass-mortality event and probability of forest loss in Central Chile.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26487\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26487\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The Mediterranean-type ecosystems of central Chile are highly biodiverse and rich in species that occur nowhere else, furthermore, they represent the entire Mediterranean biome of South America. However, Chile's Mediterranean-type ecosystems are threatened due to habitat loss and degradation due to conversion for agriculture, grazing and urbanisation, habitat fragmentation and forest fires. The escalating impacts of the climate crisis now represent a critical threat to their survival. The Chilean summer of 2022-2023 has seen sudden, severe and extensive forest mortality in central Chile. The region is experiencing a period of prolonged drought dubbed the 'Mega Drought' (MD), where precipitation has been at least 25% lower than usual since 2010. Two exceptionally dry years occurred in 2019 and 2021, with precipitation some 80% lower than average, followed by a 50% reduction in 2022. By the end of summer 2023 widespread tree death and forest ecosystem collapse was apparent. Our understanding of where drought impacts should be felt first across the geographic distribution of a species suggests that we should see these impacts concentrated in the already hotter and drier parts of species ranges. However, in the Mediterranean climate region of Central Chile we are now seeing forests dying right across their natural distribution in mountain regions - with even those occurring in cooler locations higher in the mountains succumbing to drought-driven death. Consequently, forest mortality is witnessed across the higher elevation forests typified by the tree 'Roble de Santiago\" (Santiago Oak) as well as those lower forests typified by the peumo tree (the Chilean acorn) which is usually much more drought resistant. Neither of these dominant forest- forming trees has long-lived seeds. Consequently, there is a serious risk that as the adults die on such large scale, there will be very little potential for trees to regenerate. The risk is that forest will rapidly be replaced by shrubland ecosystems which are smaller in stature, store much less carbon, are highly flammable and with very different associated biodiversity. This exceptionally widespread forest mass mortality event in Chile presents an unprecedented opportunity to help us understand the pattern, process and implications of forest ecosystem collapse. Such an opportunity is highly rare and exceptionally valuable to help us better understand the risks to our forests at the global scale. In this project, we will conduct a detailed survey of the size and distribution of dead trees, any tree regeneration that we find from seeds and shoots and similar data from shrubs. We'll also survey the seed bank to discover which species are most likely to regenerate from seed. We'll use temperature and moisture sensors throughout the forest to understand small-scale variation in the climate that the trees are experiencing and link this to regeneration and the occasions where we find tree survival. As well as the plot-level data, we will access a detailed digital landscape model and survey the tree canopy using a drone mounted camera and unite these images with the field survey data so we can understand stand and canopy structure from above and below. This drone-based data will also enable us to scale up to remote sensing data from satellites so that we can understand the mortality extent and impacts at much larger spatial scales. In combination, the data will enable us to understand the extent and impacts of mortality on the forest itself, the potential for forest regeneration and the balance between tree and shrub survival and regeneration across the landscape. It will help us to understand where and why forests are dying - and what vegetation will remain after the trees die, enabling us to better plan for the impacts of climate change and to quantify what consequences forest loss will have for local and global models of carbon uptake and storage by trees.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 23CVC-245806<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2023 - Diciembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Corporaci\u00f3n de Fomento de la Producci\u00f3n - CORFO<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25999\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Strong-Bee: Gel multi-ingredientes formulado en base a compuestos naturales, especialmente desarrollado para favorecer la recuperaci\u00f3n muscular y el rendimiento de deportistas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25999\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25999\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Desarrollar y validar mediante ensayos in vivo un gel energ\u00e9tico para deportistas de alto rendimiento, formulado en\r\nbase a miel y extractos naturales, para ser utilizado como potenciador del rendimiento deportivo y la recuperaci\u00f3n\r\nmuscular post ejercicio. Los principales objetivos son: 1) Formular el gel energ\u00e9tico en base a los requerimientos\r\nnutricionales espec\u00ed&#1048789;cos de deportistas de alto rendimiento, caracteriz\u00e1ndolo en t\u00e9rminos nutricionales, capacidad\r\nantioxidante y ausencia de sustancias no deseadas. 2)Evaluar la tolerabilidad in vivo del producto en t\u00e9rminos de\r\npalatabilidad y efectos gastrointestinales. 3)Dise\u00f1ar e implementar el proceso mezclamiento y envasado para escalar\r\nla producci\u00f3n. 4)Cuanti&#1048789;car los efectos del producto desarrollado respecto del aporte sobre el rendimiento deportivo,\r\nla recuperaci\u00f3n muscular post ejercicio y s\u00edntomas de malestar gastrointestinal. y 5) Fortalecer el modelo de negocios.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 23CVC-245806<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2023 - Diciembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Corporaci\u00f3n de Fomento de la Producci\u00f3n - CORFO<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26140\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Strong-Bee: Gel multi-ingredientes formulado en base a compuestos naturales, especialmente desarrollado para favorecer la recuperaci\u00f3n muscular y el rendimiento de deportistas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26140\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26140\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Desarrollar y validar mediante ensayos in vivo un gel energ\u00e9tico para deportistas de alto rendimiento, formulado en\r\nbase a miel y extractos naturales, para ser utilizado como potenciador del rendimiento deportivo y la recuperaci\u00f3n\r\nmuscular post ejercicio. Los principales objetivos son: 1) Formular el gel energ\u00e9tico en base a los requerimientos\r\nnutricionales espec\u00ed&#1048789;cos de deportistas de alto rendimiento, caracteriz\u00e1ndolo en t\u00e9rminos nutricionales, capacidad\r\nantioxidante y ausencia de sustancias no deseadas. 2)Evaluar la tolerabilidad in vivo del producto en t\u00e9rminos de\r\npalatabilidad y efectos gastrointestinales. 3)Dise\u00f1ar e implementar el proceso mezclamiento y envasado para escalar\r\nla producci\u00f3n. 4)Cuanti&#1048789;car los efectos del producto desarrollado respecto del aporte sobre el rendimiento deportivo,\r\nla recuperaci\u00f3n muscular post ejercicio y s\u00edntomas de malestar gastrointestinal. y 5) Fortalecer el modelo de negocios.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FONDEF IT23I0012<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2023 - Octubre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26098\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            FONDEF IT23I0012 Sistema de gesti\u00f3n pedag\u00f3gica para el aula matem\u00e1tica con base en juegos y recomendaciones inteligentes\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26098\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26098\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Esta propuesta se construye a partir de un proyecto previo (FONDEF ID19I10030) donde desarrollamos y validamos un modelo de ense\u00f1anza matem\u00e1tica con base en juegos de mesa y evaluaciones digitales para estudiantes en el nivel de transici\u00f3n de la educaci\u00f3n parvularia. Por un lado, elaboramos 12 juegos de mesa cuyos efectos positivos en el aprendizaje matem\u00e1tico se validaron a trav\u00e9s de una intervenci\u00f3n escolar controlada. Por otro lado, desarrollamos el test de pensamiento matem\u00e1tico (TPM) para evaluar objetivos curriculares matem\u00e1ticos del nivel de transici\u00f3n. El TPM utiliza tabletas para automatizar la mediaci\u00f3n, lo cual permite que su formato de aplicaci\u00f3n sea grupal, recolectando grandes cantidades de datos con poco esfuerzo y de manera inmediata (p.ej., eval\u00faa aulas completas en una hora). Datos de una muestra de 750 ni\u00f1os, permiti\u00f3 verificar su validez de contenido, criterio y constructo, para asegurar que puede ser utilizado como instrumento de evaluaci\u00f3n de los logros de aprendizaje declarados en el curr\u00edculo chileno. En consecuencia, la prueba de concepto de nuestro modelo de ense\u00f1anza fue exitoso.\r\nEstudios recientes demuestran que en Chile los procesos de capacitaci\u00f3n docente no producen mejoras en los aprendizajes estudiantiles, indicando que la superaci\u00f3n del problema de bajos desempe\u00f1os exige la creaci\u00f3n de estrategias curriculares m\u00e1s intensivas e integrales. En este contexto, el presente proyecto busca desarrollar un sistema de apoyo docente, cuyo n\u00facleo pedag\u00f3gico sea el modelo de ense\u00f1anza descrito arriba, y que pueda ser llevado con \u00e9xito a aulas reales del sistema educativo chileno. El primer resultado de este proyecto fortalece el TPM dot\u00e1ndole de la capacidad para entregar retroalimentaci\u00f3n personalizada de manera automatizada en formato de recomendaciones de actividades para mejorar los aprendizajes. Para esto, crearemos algoritmos de inteligencia artificial que ser\u00e1n entrenados a partir de un etiquetado de datos (elaborado por educadoras expertas) que asignen actividades de aprendizaje adecuadas a los resultados TPM. El segundo resultado es un sistema de apoyo docente integral e intensivo que facilita la adopci\u00f3n de nuestro modelo de ense\u00f1anza en aulas reales. Dicho sistema permite que una instituci\u00f3n p\u00fablica (p.ej., un SLEP) brinde servicios educativos dirigidos a fortalecer la calidad de los aprendizajes matem\u00e1ticos tempranos en todas las aulas de su red educativa. En m\u00e1s detalle, el \u0093sistema de gesti\u00f3n pedag\u00f3gica del aula matem\u00e1tica\u0094 coordina el uso de materiales educativos, profesionales expertos y plataformas tecnol\u00f3gicas para mejorar la calidad de los procesos de ense\u00f1anza-aprendizaje. La validaci\u00f3n de este sistema involucra realizar una intervenci\u00f3n escolar de tipo longitudinal, con grupo de control y cuatro medidas repetidas que permitan estimar su efecto en los aprendizajes matem\u00e1ticos de 400 estudiantes. Tambi\u00e9n se eval\u00faa el nivel de aceptaci\u00f3n del sistema por parte del cuerpo docente involucrado. El plan de implementaci\u00f3n y masificaci\u00f3n contempla que la Fundaci\u00f3n Mustakis (mandante) masifique al uso del TPM y el acceso a los programas de capacitaci\u00f3n on-line, el DAEM Requinoa (asociada) realice un pilotaje del sistema de gesti\u00f3n pedag\u00f3gica del aula matem\u00e1tica y que la UOH (beneficiaria) genere alianzas con instituciones p\u00fablicas (p.ej., DAEM, SLEP) para que adopten este sistema y puedan brindar servicios educativos que mejoren los aprendizajes matem\u00e1ticos en las aulas de sus redes educativas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FONDEF IT23I0012<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2023 - Octubre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26212\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            FONDEF IT23I0012 Sistema de gesti\u00f3n pedag\u00f3gica para el aula matem\u00e1tica con base en juegos y recomendaciones inteligentes\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26212\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26212\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Esta propuesta se construye a partir de un proyecto previo (FONDEF ID19I10030) donde desarrollamos y validamos un modelo de ense\u00f1anza matem\u00e1tica con base en juegos de mesa y evaluaciones digitales para estudiantes en el nivel de transici\u00f3n de la educaci\u00f3n parvularia. Por un lado, elaboramos 12 juegos de mesa cuyos efectos positivos en el aprendizaje matem\u00e1tico se validaron a trav\u00e9s de una intervenci\u00f3n escolar controlada. Por otro lado, desarrollamos el test de pensamiento matem\u00e1tico (TPM) para evaluar objetivos curriculares matem\u00e1ticos del nivel de transici\u00f3n. El TPM utiliza tabletas para automatizar la mediaci\u00f3n, lo cual permite que su formato de aplicaci\u00f3n sea grupal, recolectando grandes cantidades de datos con poco esfuerzo y de manera inmediata (p.ej., eval\u00faa aulas completas en una hora). Datos de una muestra de 750 ni\u00f1os, permiti\u00f3 verificar su validez de contenido, criterio y constructo, para asegurar que puede ser utilizado como instrumento de evaluaci\u00f3n de los logros de aprendizaje declarados en el curr\u00edculo chileno. En consecuencia, la prueba de concepto de nuestro modelo de ense\u00f1anza fue exitoso.\r\nEstudios recientes demuestran que en Chile los procesos de capacitaci\u00f3n docente no producen mejoras en los aprendizajes estudiantiles, indicando que la superaci\u00f3n del problema de bajos desempe\u00f1os exige la creaci\u00f3n de estrategias curriculares m\u00e1s intensivas e integrales. En este contexto, el presente proyecto busca desarrollar un sistema de apoyo docente, cuyo n\u00facleo pedag\u00f3gico sea el modelo de ense\u00f1anza descrito arriba, y que pueda ser llevado con \u00e9xito a aulas reales del sistema educativo chileno. El primer resultado de este proyecto fortalece el TPM dot\u00e1ndole de la capacidad para entregar retroalimentaci\u00f3n personalizada de manera automatizada en formato de recomendaciones de actividades para mejorar los aprendizajes. Para esto, crearemos algoritmos de inteligencia artificial que ser\u00e1n entrenados a partir de un etiquetado de datos (elaborado por educadoras expertas) que asignen actividades de aprendizaje adecuadas a los resultados TPM. El segundo resultado es un sistema de apoyo docente integral e intensivo que facilita la adopci\u00f3n de nuestro modelo de ense\u00f1anza en aulas reales. Dicho sistema permite que una instituci\u00f3n p\u00fablica (p.ej., un SLEP) brinde servicios educativos dirigidos a fortalecer la calidad de los aprendizajes matem\u00e1ticos tempranos en todas las aulas de su red educativa. En m\u00e1s detalle, el \u0093sistema de gesti\u00f3n pedag\u00f3gica del aula matem\u00e1tica\u0094 coordina el uso de materiales educativos, profesionales expertos y plataformas tecnol\u00f3gicas para mejorar la calidad de los procesos de ense\u00f1anza-aprendizaje. La validaci\u00f3n de este sistema involucra realizar una intervenci\u00f3n escolar de tipo longitudinal, con grupo de control y cuatro medidas repetidas que permitan estimar su efecto en los aprendizajes matem\u00e1ticos de 400 estudiantes. Tambi\u00e9n se eval\u00faa el nivel de aceptaci\u00f3n del sistema por parte del cuerpo docente involucrado. El plan de implementaci\u00f3n y masificaci\u00f3n contempla que la Fundaci\u00f3n Mustakis (mandante) masifique al uso del TPM y el acceso a los programas de capacitaci\u00f3n on-line, el DAEM Requinoa (asociada) realice un pilotaje del sistema de gesti\u00f3n pedag\u00f3gica del aula matem\u00e1tica y que la UOH (beneficiaria) genere alianzas con instituciones p\u00fablicas (p.ej., DAEM, SLEP) para que adopten este sistema y puedan brindar servicios educativos que mejoren los aprendizajes matem\u00e1ticos en las aulas de sus redes educativas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FONDEF IT23I0012<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2023 - Octubre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26700\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            FONDEF IT23I0012 Sistema de gesti\u00f3n pedag\u00f3gica para el aula matem\u00e1tica con base en juegos y recomendaciones inteligentes\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26700\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26700\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Esta propuesta se construye a partir de un proyecto previo (FONDEF ID19I10030) donde desarrollamos y validamos un modelo de ense\u00f1anza matem\u00e1tica con base en juegos de mesa y evaluaciones digitales para estudiantes en el nivel de transici\u00f3n de la educaci\u00f3n parvularia. Por un lado, elaboramos 12 juegos de mesa cuyos efectos positivos en el aprendizaje matem\u00e1tico se validaron a trav\u00e9s de una intervenci\u00f3n escolar controlada. Por otro lado, desarrollamos el test de pensamiento matem\u00e1tico (TPM) para evaluar objetivos curriculares matem\u00e1ticos del nivel de transici\u00f3n. El TPM utiliza tabletas para automatizar la mediaci\u00f3n, lo cual permite que su formato de aplicaci\u00f3n sea grupal, recolectando grandes cantidades de datos con poco esfuerzo y de manera inmediata (p.ej., eval\u00faa aulas completas en una hora). Datos de una muestra de 750 ni\u00f1os, permiti\u00f3 verificar su validez de contenido, criterio y constructo, para asegurar que puede ser utilizado como instrumento de evaluaci\u00f3n de los logros de aprendizaje declarados en el curr\u00edculo chileno. En consecuencia, la prueba de concepto de nuestro modelo de ense\u00f1anza fue exitoso.\r\nEstudios recientes demuestran que en Chile los procesos de capacitaci\u00f3n docente no producen mejoras en los aprendizajes estudiantiles, indicando que la superaci\u00f3n del problema de bajos desempe\u00f1os exige la creaci\u00f3n de estrategias curriculares m\u00e1s intensivas e integrales. En este contexto, el presente proyecto busca desarrollar un sistema de apoyo docente, cuyo n\u00facleo pedag\u00f3gico sea el modelo de ense\u00f1anza descrito arriba, y que pueda ser llevado con \u00e9xito a aulas reales del sistema educativo chileno. El primer resultado de este proyecto fortalece el TPM dot\u00e1ndole de la capacidad para entregar retroalimentaci\u00f3n personalizada de manera automatizada en formato de recomendaciones de actividades para mejorar los aprendizajes. Para esto, crearemos algoritmos de inteligencia artificial que ser\u00e1n entrenados a partir de un etiquetado de datos (elaborado por educadoras expertas) que asignen actividades de aprendizaje adecuadas a los resultados TPM. El segundo resultado es un sistema de apoyo docente integral e intensivo que facilita la adopci\u00f3n de nuestro modelo de ense\u00f1anza en aulas reales. Dicho sistema permite que una instituci\u00f3n p\u00fablica (p.ej., un SLEP) brinde servicios educativos dirigidos a fortalecer la calidad de los aprendizajes matem\u00e1ticos tempranos en todas las aulas de su red educativa. En m\u00e1s detalle, el \u0093sistema de gesti\u00f3n pedag\u00f3gica del aula matem\u00e1tica\u0094 coordina el uso de materiales educativos, profesionales expertos y plataformas tecnol\u00f3gicas para mejorar la calidad de los procesos de ense\u00f1anza-aprendizaje. La validaci\u00f3n de este sistema involucra realizar una intervenci\u00f3n escolar de tipo longitudinal, con grupo de control y cuatro medidas repetidas que permitan estimar su efecto en los aprendizajes matem\u00e1ticos de 400 estudiantes. Tambi\u00e9n se eval\u00faa el nivel de aceptaci\u00f3n del sistema por parte del cuerpo docente involucrado. El plan de implementaci\u00f3n y masificaci\u00f3n contempla que la Fundaci\u00f3n Mustakis (mandante) masifique al uso del TPM y el acceso a los programas de capacitaci\u00f3n on-line, el DAEM Requinoa (asociada) realice un pilotaje del sistema de gesti\u00f3n pedag\u00f3gica del aula matem\u00e1tica y que la UOH (beneficiaria) genere alianzas con instituciones p\u00fablicas (p.ej., DAEM, SLEP) para que adopten este sistema y puedan brindar servicios educativos que mejoren los aprendizajes matem\u00e1ticos en las aulas de sus redes educativas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2023 - Junio 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Consejo Latinoamericano de Ciencias Sociales (CLACSO)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26955\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26955\" aria-expanded=\"false\" aria-controls=\"collapse-26955\">\n                                            Experiencias del Movimiento Social de la Discapacidad en Am\u00e9rica Latina: Itinerarios de lucha por los derechos del Colectivo Nacional por la Discapacidad de Chile y la Asociaci\u00f3n de Discapacidad del Guayas de Ecuador\u0094.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26955\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26955\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Experiencias del Movimiento Social de la Discapacidad en Am\u00e9rica Latina: Itinerarios de lucha por los derechos del Colectivo Nacional por la Discapacidad de Chile y la Asociaci\u00f3n de Discapacidad del Guayas de Ecuador.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2023 - Septiembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26141\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Centro UOH de BioIngenier\u00eda (CUBI)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26141\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26141\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto interno de la UOH de car\u00e1cter multidisciplinario que busca crear mapas moleculares multi\u00f3micos de los c\u00e1nceres prevalentes en la regi\u00f3n, utilizando tecnolog\u00edas de vanguardia y algoritmos avanzados.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2023 - Septiembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26948\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Centro UOH de BioIngenier\u00eda (CUBI)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26948\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26948\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto interno de la UOH de car\u00e1cter multidisciplinario que busca crear mapas moleculares multi\u00f3micos de los c\u00e1nceres prevalentes en la regi\u00f3n, utilizando tecnolog\u00edas de vanguardia y algoritmos avanzados.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2023 - Septiembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27035\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Centro UOH de BioIngenier\u00eda (CUBI)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27035\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27035\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto interno de la UOH de car\u00e1cter multidisciplinario que busca crear mapas moleculares multi\u00f3micos de los c\u00e1nceres prevalentes en la regi\u00f3n, utilizando tecnolog\u00edas de vanguardia y algoritmos avanzados.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> CON203020019<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2023 - Septiembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26066\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Consorcio del Valle Central de Chile: una propuesta territorial,  regional y estatal para la innovaci\u00f3n, desarrollo y fortalecimiento de las artes, humanidades y ciencias sociales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26066\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26066\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las regiones de O\u0092Higgins y el Maule tienen una historia com\u00fan, caracter\u00edsticas y un desarrollo similar. Ambas regiones, ubicadas en el Valle Central chileno, comparten elementos culturales, s\u00edmbolos, historias, personajes y personas. Estas dos regiones, caracterizadas por una fuerte componente agr\u00edcola, han vivido la migraci\u00f3n rural-urbana y la transformaci\u00f3n del mundo agr\u00edcola en distintas componentes. Debido a las importantes similitudes territoriales, humanas y productivas que poseen las regiones de O\u0092Higgins y el Maule, es que las universidades estatales de ambos territorios proponen un trabajo consorciado de fortalecimiento de las artes, humanidades y ciencias sociales. Su objetivo es crear un plan de desarrollo (estrat\u00e9gico y de implementaci\u00f3n) de corto, mediano y largo plazo para el fortalecimiento de las Artes, Humanidades y Ciencias Sociales en las unidades postulantes de las Universidades de Talca y O\u0092Higgins, incorporando inter-transdisciplina (I-TD) y sinergia interuniversitaria (S-IU), que permita transformar de manera innovadora procesos acad\u00e9micos de gesti\u00f3n y gobernanza,\r\nformaci\u00f3n de pre y postgrado, generaci\u00f3n y transferencia de nuevo conocimiento, creaci\u00f3n y tecnolog\u00eda, v\u00ednculo territorial bidireccional con el medio que las cobija y, promover transversalmente la equidad de g\u00e9nero y el liderazgo femenino, los derechos humanos, el patrimonio cultural, la salud mental y el bienestar psicol\u00f3gico,\r\npara as\u00ed aportar conjuntamente a las necesidades regionales y al logro de una mejor calidad de vida de los actuales y futuros habitantes de sus comunidades.\r\n\r\nTanto la Universidad de Talca como la Universidad de O\u0092Higgins tiene capacidades instaladas en estas \u00e1reas con distintos niveles desarrollo. En el caso de la  Universidad de Talca, las unidades acad\u00e9micas pertinentes a este concurso son las Facultades de: Psicolog\u00eda, Ciencias Jur\u00eddicas y Ciencias Sociales, Arquitectura, M\u00fasica y Dise\u00f1o; y el Instituto de Humanidades Abate Molina. En el caso de la Universidad de O\u0092Higgins las unidades acad\u00e9micas relevantes son el Instituto de Ciencias Sociales, la Escuela de Ciencias Sociales y el Instituto de Altos Estudios\r\nAudiovisuales.\r\n\r\nPara el desarrollo del proyecto, adem\u00e1s del trabajo de los directores, se realizar\u00e1 la contrataci\u00f3n de profesionales para tareas de gesti\u00f3n y planificaci\u00f3n del proyecto. Las autoridades de ambas universidades (rectores, vicerrectores, decanos\/as, entre otros) interactuar\u00e1n con el equipo mediante un consejo estrat\u00e9gico. Adem\u00e1s,\r\nse conformar\u00e1 una mesa de coordinaci\u00f3n interinstitucional que se organizar\u00e1 por ejes, considerando un coordinador\/a por eje estrat\u00e9gico.\r\n\r\nLa elaboraci\u00f3n del diagn\u00f3stico se centra en procesos participativos liderados por equipos internos que propicien la apropiaci\u00f3n de los resultados y contempla 4 etapas. La primera etapa de autoevaluaci\u00f3n seg\u00fan eje estrat\u00e9gico se centra en el levantamiento, sistematizaci\u00f3n y an\u00e1lisis de la situaci\u00f3n interna de ambas universidades. La segunda etapa de aplicaci\u00f3n de instrumentos de recolecci\u00f3n de antecedentes, de car\u00e1cter mixto y en terreno, tiene como prop\u00f3sito indagar en las brechas, expectativas y necesidades de los actores internos y externos, con\r\nrelaci\u00f3n a la transferencia de conocimientos y tecnolog\u00edas, vinculaci\u00f3n universidad-territorio, liderazgo femenino, oferta formativa en artes, humanidades y ciencias sociales, gobernanza, ciencia y conocimientos abiertos de parte de ambas instituciones. Esta etapa se realizar\u00e1 mediante entrevistas abiertas a actores claves, talleres participativos con miembros de la comunidad y entrevistas semiestructuradas a autoridades universitarias, comunales, provinciales y regionales. En la tercera etapa, de traducci\u00f3n del diagn\u00f3stico, se realizar\u00e1 la sistematizaci\u00f3n y categorizaci\u00f3n de la informaci\u00f3n obtenida en las etapas anteriores, utilizando como metodolog\u00eda el an\u00e1lisis de texto y categorizaci\u00f3n conceptual, junto con una triangulaci\u00f3n de los datos cuantitativos y cualitativos recabados tanto internamente en cada universidad como en el medio regional del Maule y O\u0092Higgins, teniendo como resultado un informe diagn\u00f3stico a ser validado, el que incluir\u00e1 una matriz con informaci\u00f3n sistematizada por eje tem\u00e1tico y la l\u00ednea base de indicadores. La cuarta y \u00faltima etapa consiste en la validaci\u00f3n del diagn\u00f3stico, a trav\u00e9s de la presentaci\u00f3n de los resultados a una red compuesta por diversos actores: representantes de la comunidad participante, expertos nacionales e internacionales, integrantes de la\r\nmesa de coordinaci\u00f3n interinstitucional, autoridades gubernamentales y, finalmente, a instancias colegiadas y autoridades unipersonales de ambas instituciones.\r\nPosterior del diagn\u00f3stico, se realizar\u00e1 un proceso de experiencia comparada, con la idea de observar los desarrollos de los diferentes ejes en otras instituciones de educaci\u00f3n superior nacionales e internacionales. Toda esta informaci\u00f3n permitir\u00e1 avanzar a la etapa de identificaci\u00f3n de brechas para identificar, por una partes,\r\nnuestra l\u00ednea de base y por otra la distancia de nuestro desarrollo con la experiencia de otras instituciones, considerando los contextos. Finalmente, estos insumos permitir\u00e1n, que de manera participativa con la comunidad universitaria y representantes de la comunidad regional, se elabore una propuesta de plan\r\nestrat\u00e9gico, que ser\u00e1 validado con actores internos y externos; y que se convertir\u00e1 en la hoja de ruta para los\r\npr\u00f3ximos a\u00f1os.\r\n\r\nEl presente proyecto se relaciona sin\u00e9rgicamente con los proyectos en desarrollo de Ingenier\u00eda 2030 y Ciencia 2030, que se encuentran en ejecuci\u00f3n en la Universidad de Talca. Estos proyectos buscan transformar las facultades de ciencias hacia una mayor vinculaci\u00f3n con el entorno mediante la I+D+i+ebct y transformar los\r\nplanes de formaci\u00f3n para las ingenier\u00edas, siendo coherente con el objetivo propuesto para la presente convocatoria. Por otra parte, la Universidad de Talca y la Universidad de O'Higgins cuentan con diversos organismos internos que pueden potenciar el trabajo del proyecto como la Direcci\u00f3n de Innovaci\u00f3n y transferencia, la Direcci\u00f3n de\r\nInvestigaci\u00f3n, Direcci\u00f3n General de Vinculaci\u00f3n con el Medio, Direcci\u00f3n General de Aseguramiento de la Calidad y Planificaci\u00f3n, Direcci\u00f3n de G\u00e9nero en el caso de la Universidad de Talca y la Direcci\u00f3n de Investigaci\u00f3n, Direcci\u00f3n de Vinculaci\u00f3n y Transferencia, Direcci\u00f3n de Postgrado, Direcci\u00f3n de Comunicaciones, Direcci\u00f3n de\r\nInternacionalizaci\u00f3n y Direcci\u00f3n de Equidad de G\u00e9nero y Diversidades en el caso de la Universidad de O'Higgins. Por \u00faltimo, la Universidad de Talca se encuentra desarrollando diferentes proyectos como Proyecto InES Redit,\r\nProyecto InES G\u00e9nero, Proyecto InEs I+D, Proyecto Ciencia Abierta, que buscan consolidar un modelo de gesti\u00f3n de la innovaci\u00f3n y emprendimiento basado en I+D interdisciplinario y transdisciplinario con perspectiva de g\u00e9nero, por una parte; as\u00ed como fortalecer y consolidar las capacidades institucionales actuales de soporte al\r\nproceso de innovaci\u00f3n basada en I+D por otra.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> CON203020019<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2023 - Septiembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26078\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Consorcio del Valle Central de Chile: una propuesta territorial,  regional y estatal para la innovaci\u00f3n, desarrollo y fortalecimiento de las artes, humanidades y ciencias sociales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26078\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26078\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las regiones de O\u0092Higgins y el Maule tienen una historia com\u00fan, caracter\u00edsticas y un desarrollo similar. Ambas regiones, ubicadas en el Valle Central chileno, comparten elementos culturales, s\u00edmbolos, historias, personajes y personas. Estas dos regiones, caracterizadas por una fuerte componente agr\u00edcola, han vivido la migraci\u00f3n rural-urbana y la transformaci\u00f3n del mundo agr\u00edcola en distintas componentes. Debido a las importantes similitudes territoriales, humanas y productivas que poseen las regiones de O\u0092Higgins y el Maule, es que las universidades estatales de ambos territorios proponen un trabajo consorciado de fortalecimiento de las artes, humanidades y ciencias sociales. Su objetivo es crear un plan de desarrollo (estrat\u00e9gico y de implementaci\u00f3n) de corto, mediano y largo plazo para el fortalecimiento de las Artes, Humanidades y Ciencias Sociales en las unidades postulantes de las Universidades de Talca y O\u0092Higgins, incorporando inter-transdisciplina (I-TD) y sinergia interuniversitaria (S-IU), que permita transformar de manera innovadora procesos acad\u00e9micos de gesti\u00f3n y gobernanza,\r\nformaci\u00f3n de pre y postgrado, generaci\u00f3n y transferencia de nuevo conocimiento, creaci\u00f3n y tecnolog\u00eda, v\u00ednculo territorial bidireccional con el medio que las cobija y, promover transversalmente la equidad de g\u00e9nero y el liderazgo femenino, los derechos humanos, el patrimonio cultural, la salud mental y el bienestar psicol\u00f3gico,\r\npara as\u00ed aportar conjuntamente a las necesidades regionales y al logro de una mejor calidad de vida de los actuales y futuros habitantes de sus comunidades.\r\n\r\nTanto la Universidad de Talca como la Universidad de O\u0092Higgins tiene capacidades instaladas en estas \u00e1reas con distintos niveles desarrollo. En el caso de la  Universidad de Talca, las unidades acad\u00e9micas pertinentes a este concurso son las Facultades de: Psicolog\u00eda, Ciencias Jur\u00eddicas y Ciencias Sociales, Arquitectura, M\u00fasica y Dise\u00f1o; y el Instituto de Humanidades Abate Molina. En el caso de la Universidad de O\u0092Higgins las unidades acad\u00e9micas relevantes son el Instituto de Ciencias Sociales, la Escuela de Ciencias Sociales y el Instituto de Altos Estudios\r\nAudiovisuales.\r\n\r\nPara el desarrollo del proyecto, adem\u00e1s del trabajo de los directores, se realizar\u00e1 la contrataci\u00f3n de profesionales para tareas de gesti\u00f3n y planificaci\u00f3n del proyecto. Las autoridades de ambas universidades (rectores, vicerrectores, decanos\/as, entre otros) interactuar\u00e1n con el equipo mediante un consejo estrat\u00e9gico. Adem\u00e1s,\r\nse conformar\u00e1 una mesa de coordinaci\u00f3n interinstitucional que se organizar\u00e1 por ejes, considerando un coordinador\/a por eje estrat\u00e9gico.\r\n\r\nLa elaboraci\u00f3n del diagn\u00f3stico se centra en procesos participativos liderados por equipos internos que propicien la apropiaci\u00f3n de los resultados y contempla 4 etapas. La primera etapa de autoevaluaci\u00f3n seg\u00fan eje estrat\u00e9gico se centra en el levantamiento, sistematizaci\u00f3n y an\u00e1lisis de la situaci\u00f3n interna de ambas universidades. La segunda etapa de aplicaci\u00f3n de instrumentos de recolecci\u00f3n de antecedentes, de car\u00e1cter mixto y en terreno, tiene como prop\u00f3sito indagar en las brechas, expectativas y necesidades de los actores internos y externos, con\r\nrelaci\u00f3n a la transferencia de conocimientos y tecnolog\u00edas, vinculaci\u00f3n universidad-territorio, liderazgo femenino, oferta formativa en artes, humanidades y ciencias sociales, gobernanza, ciencia y conocimientos abiertos de parte de ambas instituciones. Esta etapa se realizar\u00e1 mediante entrevistas abiertas a actores claves, talleres participativos con miembros de la comunidad y entrevistas semiestructuradas a autoridades universitarias, comunales, provinciales y regionales. En la tercera etapa, de traducci\u00f3n del diagn\u00f3stico, se realizar\u00e1 la sistematizaci\u00f3n y categorizaci\u00f3n de la informaci\u00f3n obtenida en las etapas anteriores, utilizando como metodolog\u00eda el an\u00e1lisis de texto y categorizaci\u00f3n conceptual, junto con una triangulaci\u00f3n de los datos cuantitativos y cualitativos recabados tanto internamente en cada universidad como en el medio regional del Maule y O\u0092Higgins, teniendo como resultado un informe diagn\u00f3stico a ser validado, el que incluir\u00e1 una matriz con informaci\u00f3n sistematizada por eje tem\u00e1tico y la l\u00ednea base de indicadores. La cuarta y \u00faltima etapa consiste en la validaci\u00f3n del diagn\u00f3stico, a trav\u00e9s de la presentaci\u00f3n de los resultados a una red compuesta por diversos actores: representantes de la comunidad participante, expertos nacionales e internacionales, integrantes de la\r\nmesa de coordinaci\u00f3n interinstitucional, autoridades gubernamentales y, finalmente, a instancias colegiadas y autoridades unipersonales de ambas instituciones.\r\nPosterior del diagn\u00f3stico, se realizar\u00e1 un proceso de experiencia comparada, con la idea de observar los desarrollos de los diferentes ejes en otras instituciones de educaci\u00f3n superior nacionales e internacionales. Toda esta informaci\u00f3n permitir\u00e1 avanzar a la etapa de identificaci\u00f3n de brechas para identificar, por una partes,\r\nnuestra l\u00ednea de base y por otra la distancia de nuestro desarrollo con la experiencia de otras instituciones, considerando los contextos. Finalmente, estos insumos permitir\u00e1n, que de manera participativa con la comunidad universitaria y representantes de la comunidad regional, se elabore una propuesta de plan\r\nestrat\u00e9gico, que ser\u00e1 validado con actores internos y externos; y que se convertir\u00e1 en la hoja de ruta para los\r\npr\u00f3ximos a\u00f1os.\r\n\r\nEl presente proyecto se relaciona sin\u00e9rgicamente con los proyectos en desarrollo de Ingenier\u00eda 2030 y Ciencia 2030, que se encuentran en ejecuci\u00f3n en la Universidad de Talca. Estos proyectos buscan transformar las facultades de ciencias hacia una mayor vinculaci\u00f3n con el entorno mediante la I+D+i+ebct y transformar los\r\nplanes de formaci\u00f3n para las ingenier\u00edas, siendo coherente con el objetivo propuesto para la presente convocatoria. Por otra parte, la Universidad de Talca y la Universidad de O'Higgins cuentan con diversos organismos internos que pueden potenciar el trabajo del proyecto como la Direcci\u00f3n de Innovaci\u00f3n y transferencia, la Direcci\u00f3n de\r\nInvestigaci\u00f3n, Direcci\u00f3n General de Vinculaci\u00f3n con el Medio, Direcci\u00f3n General de Aseguramiento de la Calidad y Planificaci\u00f3n, Direcci\u00f3n de G\u00e9nero en el caso de la Universidad de Talca y la Direcci\u00f3n de Investigaci\u00f3n, Direcci\u00f3n de Vinculaci\u00f3n y Transferencia, Direcci\u00f3n de Postgrado, Direcci\u00f3n de Comunicaciones, Direcci\u00f3n de\r\nInternacionalizaci\u00f3n y Direcci\u00f3n de Equidad de G\u00e9nero y Diversidades en el caso de la Universidad de O'Higgins. Por \u00faltimo, la Universidad de Talca se encuentra desarrollando diferentes proyectos como Proyecto InES Redit,\r\nProyecto InES G\u00e9nero, Proyecto InEs I+D, Proyecto Ciencia Abierta, que buscan consolidar un modelo de gesti\u00f3n de la innovaci\u00f3n y emprendimiento basado en I+D interdisciplinario y transdisciplinario con perspectiva de g\u00e9nero, por una parte; as\u00ed como fortalecer y consolidar las capacidades institucionales actuales de soporte al\r\nproceso de innovaci\u00f3n basada en I+D por otra.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> CON203020019<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2023 - Septiembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26107\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Consorcio del Valle Central de Chile: una propuesta territorial,  regional y estatal para la innovaci\u00f3n, desarrollo y fortalecimiento de las artes, humanidades y ciencias sociales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26107\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26107\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las regiones de O\u0092Higgins y el Maule tienen una historia com\u00fan, caracter\u00edsticas y un desarrollo similar. Ambas regiones, ubicadas en el Valle Central chileno, comparten elementos culturales, s\u00edmbolos, historias, personajes y personas. Estas dos regiones, caracterizadas por una fuerte componente agr\u00edcola, han vivido la migraci\u00f3n rural-urbana y la transformaci\u00f3n del mundo agr\u00edcola en distintas componentes. Debido a las importantes similitudes territoriales, humanas y productivas que poseen las regiones de O\u0092Higgins y el Maule, es que las universidades estatales de ambos territorios proponen un trabajo consorciado de fortalecimiento de las artes, humanidades y ciencias sociales. Su objetivo es crear un plan de desarrollo (estrat\u00e9gico y de implementaci\u00f3n) de corto, mediano y largo plazo para el fortalecimiento de las Artes, Humanidades y Ciencias Sociales en las unidades postulantes de las Universidades de Talca y O\u0092Higgins, incorporando inter-transdisciplina (I-TD) y sinergia interuniversitaria (S-IU), que permita transformar de manera innovadora procesos acad\u00e9micos de gesti\u00f3n y gobernanza,\r\nformaci\u00f3n de pre y postgrado, generaci\u00f3n y transferencia de nuevo conocimiento, creaci\u00f3n y tecnolog\u00eda, v\u00ednculo territorial bidireccional con el medio que las cobija y, promover transversalmente la equidad de g\u00e9nero y el liderazgo femenino, los derechos humanos, el patrimonio cultural, la salud mental y el bienestar psicol\u00f3gico,\r\npara as\u00ed aportar conjuntamente a las necesidades regionales y al logro de una mejor calidad de vida de los actuales y futuros habitantes de sus comunidades.\r\n\r\nTanto la Universidad de Talca como la Universidad de O\u0092Higgins tiene capacidades instaladas en estas \u00e1reas con distintos niveles desarrollo. En el caso de la  Universidad de Talca, las unidades acad\u00e9micas pertinentes a este concurso son las Facultades de: Psicolog\u00eda, Ciencias Jur\u00eddicas y Ciencias Sociales, Arquitectura, M\u00fasica y Dise\u00f1o; y el Instituto de Humanidades Abate Molina. En el caso de la Universidad de O\u0092Higgins las unidades acad\u00e9micas relevantes son el Instituto de Ciencias Sociales, la Escuela de Ciencias Sociales y el Instituto de Altos Estudios\r\nAudiovisuales.\r\n\r\nPara el desarrollo del proyecto, adem\u00e1s del trabajo de los directores, se realizar\u00e1 la contrataci\u00f3n de profesionales para tareas de gesti\u00f3n y planificaci\u00f3n del proyecto. Las autoridades de ambas universidades (rectores, vicerrectores, decanos\/as, entre otros) interactuar\u00e1n con el equipo mediante un consejo estrat\u00e9gico. Adem\u00e1s,\r\nse conformar\u00e1 una mesa de coordinaci\u00f3n interinstitucional que se organizar\u00e1 por ejes, considerando un coordinador\/a por eje estrat\u00e9gico.\r\n\r\nLa elaboraci\u00f3n del diagn\u00f3stico se centra en procesos participativos liderados por equipos internos que propicien la apropiaci\u00f3n de los resultados y contempla 4 etapas. La primera etapa de autoevaluaci\u00f3n seg\u00fan eje estrat\u00e9gico se centra en el levantamiento, sistematizaci\u00f3n y an\u00e1lisis de la situaci\u00f3n interna de ambas universidades. La segunda etapa de aplicaci\u00f3n de instrumentos de recolecci\u00f3n de antecedentes, de car\u00e1cter mixto y en terreno, tiene como prop\u00f3sito indagar en las brechas, expectativas y necesidades de los actores internos y externos, con\r\nrelaci\u00f3n a la transferencia de conocimientos y tecnolog\u00edas, vinculaci\u00f3n universidad-territorio, liderazgo femenino, oferta formativa en artes, humanidades y ciencias sociales, gobernanza, ciencia y conocimientos abiertos de parte de ambas instituciones. Esta etapa se realizar\u00e1 mediante entrevistas abiertas a actores claves, talleres participativos con miembros de la comunidad y entrevistas semiestructuradas a autoridades universitarias, comunales, provinciales y regionales. En la tercera etapa, de traducci\u00f3n del diagn\u00f3stico, se realizar\u00e1 la sistematizaci\u00f3n y categorizaci\u00f3n de la informaci\u00f3n obtenida en las etapas anteriores, utilizando como metodolog\u00eda el an\u00e1lisis de texto y categorizaci\u00f3n conceptual, junto con una triangulaci\u00f3n de los datos cuantitativos y cualitativos recabados tanto internamente en cada universidad como en el medio regional del Maule y O\u0092Higgins, teniendo como resultado un informe diagn\u00f3stico a ser validado, el que incluir\u00e1 una matriz con informaci\u00f3n sistematizada por eje tem\u00e1tico y la l\u00ednea base de indicadores. La cuarta y \u00faltima etapa consiste en la validaci\u00f3n del diagn\u00f3stico, a trav\u00e9s de la presentaci\u00f3n de los resultados a una red compuesta por diversos actores: representantes de la comunidad participante, expertos nacionales e internacionales, integrantes de la\r\nmesa de coordinaci\u00f3n interinstitucional, autoridades gubernamentales y, finalmente, a instancias colegiadas y autoridades unipersonales de ambas instituciones.\r\nPosterior del diagn\u00f3stico, se realizar\u00e1 un proceso de experiencia comparada, con la idea de observar los desarrollos de los diferentes ejes en otras instituciones de educaci\u00f3n superior nacionales e internacionales. Toda esta informaci\u00f3n permitir\u00e1 avanzar a la etapa de identificaci\u00f3n de brechas para identificar, por una partes,\r\nnuestra l\u00ednea de base y por otra la distancia de nuestro desarrollo con la experiencia de otras instituciones, considerando los contextos. Finalmente, estos insumos permitir\u00e1n, que de manera participativa con la comunidad universitaria y representantes de la comunidad regional, se elabore una propuesta de plan\r\nestrat\u00e9gico, que ser\u00e1 validado con actores internos y externos; y que se convertir\u00e1 en la hoja de ruta para los\r\npr\u00f3ximos a\u00f1os.\r\n\r\nEl presente proyecto se relaciona sin\u00e9rgicamente con los proyectos en desarrollo de Ingenier\u00eda 2030 y Ciencia 2030, que se encuentran en ejecuci\u00f3n en la Universidad de Talca. Estos proyectos buscan transformar las facultades de ciencias hacia una mayor vinculaci\u00f3n con el entorno mediante la I+D+i+ebct y transformar los\r\nplanes de formaci\u00f3n para las ingenier\u00edas, siendo coherente con el objetivo propuesto para la presente convocatoria. Por otra parte, la Universidad de Talca y la Universidad de O'Higgins cuentan con diversos organismos internos que pueden potenciar el trabajo del proyecto como la Direcci\u00f3n de Innovaci\u00f3n y transferencia, la Direcci\u00f3n de\r\nInvestigaci\u00f3n, Direcci\u00f3n General de Vinculaci\u00f3n con el Medio, Direcci\u00f3n General de Aseguramiento de la Calidad y Planificaci\u00f3n, Direcci\u00f3n de G\u00e9nero en el caso de la Universidad de Talca y la Direcci\u00f3n de Investigaci\u00f3n, Direcci\u00f3n de Vinculaci\u00f3n y Transferencia, Direcci\u00f3n de Postgrado, Direcci\u00f3n de Comunicaciones, Direcci\u00f3n de\r\nInternacionalizaci\u00f3n y Direcci\u00f3n de Equidad de G\u00e9nero y Diversidades en el caso de la Universidad de O'Higgins. Por \u00faltimo, la Universidad de Talca se encuentra desarrollando diferentes proyectos como Proyecto InES Redit,\r\nProyecto InES G\u00e9nero, Proyecto InEs I+D, Proyecto Ciencia Abierta, que buscan consolidar un modelo de gesti\u00f3n de la innovaci\u00f3n y emprendimiento basado en I+D interdisciplinario y transdisciplinario con perspectiva de g\u00e9nero, por una parte; as\u00ed como fortalecer y consolidar las capacidades institucionales actuales de soporte al\r\nproceso de innovaci\u00f3n basada en I+D por otra.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> id23i10335<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2023 - Agosto 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26209\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Modelo de integraci\u00f3n del pensamiento computacional y la programaci\u00f3n en la formaci\u00f3n inicial docente\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26209\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26209\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La soluci\u00f3n que se propone en este proyecto es el desarrollo de un Modelo de Integraci\u00f3n de Pensamiento Computacional y Programaci\u00f3n para la Formaci\u00f3n Inicial Docente (en adelante, \u0093Modelo de Integraci\u00f3n PCyP para la FID\u0094). Esto corresponde a un modelo formativo flexible que pueda ser adoptado por distintas instituciones de educaci\u00f3n superior que deseen actualizar sus mallas curriculares y programas incorporando PCyP en sus carreras de pedagog\u00eda. Se busca que este modelo sea un desarrollo innovador que pueda ser aplicado en el entorno real de la educaci\u00f3n superior, dirigido espec\u00edficamente a las carreras de pedagog\u00eda, de modo de generar el capital humano que Chile necesita para poder desarrollar y aplicar estrategias de ense\u00f1anza-aprendizaje del PCyP en las aulas del pa\u00eds.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> CON203020019<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2023 - Septiembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26442\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Consorcio del Valle Central de Chile: una propuesta territorial,  regional y estatal para la innovaci\u00f3n, desarrollo y fortalecimiento de las artes, humanidades y ciencias sociales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26442\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26442\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las regiones de O\u0092Higgins y el Maule tienen una historia com\u00fan, caracter\u00edsticas y un desarrollo similar. Ambas regiones, ubicadas en el Valle Central chileno, comparten elementos culturales, s\u00edmbolos, historias, personajes y personas. Estas dos regiones, caracterizadas por una fuerte componente agr\u00edcola, han vivido la migraci\u00f3n rural-urbana y la transformaci\u00f3n del mundo agr\u00edcola en distintas componentes. Debido a las importantes similitudes territoriales, humanas y productivas que poseen las regiones de O\u0092Higgins y el Maule, es que las universidades estatales de ambos territorios proponen un trabajo consorciado de fortalecimiento de las artes, humanidades y ciencias sociales. Su objetivo es crear un plan de desarrollo (estrat\u00e9gico y de implementaci\u00f3n) de corto, mediano y largo plazo para el fortalecimiento de las Artes, Humanidades y Ciencias Sociales en las unidades postulantes de las Universidades de Talca y O\u0092Higgins, incorporando inter-transdisciplina (I-TD) y sinergia interuniversitaria (S-IU), que permita transformar de manera innovadora procesos acad\u00e9micos de gesti\u00f3n y gobernanza,\r\nformaci\u00f3n de pre y postgrado, generaci\u00f3n y transferencia de nuevo conocimiento, creaci\u00f3n y tecnolog\u00eda, v\u00ednculo territorial bidireccional con el medio que las cobija y, promover transversalmente la equidad de g\u00e9nero y el liderazgo femenino, los derechos humanos, el patrimonio cultural, la salud mental y el bienestar psicol\u00f3gico,\r\npara as\u00ed aportar conjuntamente a las necesidades regionales y al logro de una mejor calidad de vida de los actuales y futuros habitantes de sus comunidades.\r\n\r\nTanto la Universidad de Talca como la Universidad de O\u0092Higgins tiene capacidades instaladas en estas \u00e1reas con distintos niveles desarrollo. En el caso de la  Universidad de Talca, las unidades acad\u00e9micas pertinentes a este concurso son las Facultades de: Psicolog\u00eda, Ciencias Jur\u00eddicas y Ciencias Sociales, Arquitectura, M\u00fasica y Dise\u00f1o; y el Instituto de Humanidades Abate Molina. En el caso de la Universidad de O\u0092Higgins las unidades acad\u00e9micas relevantes son el Instituto de Ciencias Sociales, la Escuela de Ciencias Sociales y el Instituto de Altos Estudios\r\nAudiovisuales.\r\n\r\nPara el desarrollo del proyecto, adem\u00e1s del trabajo de los directores, se realizar\u00e1 la contrataci\u00f3n de profesionales para tareas de gesti\u00f3n y planificaci\u00f3n del proyecto. Las autoridades de ambas universidades (rectores, vicerrectores, decanos\/as, entre otros) interactuar\u00e1n con el equipo mediante un consejo estrat\u00e9gico. Adem\u00e1s,\r\nse conformar\u00e1 una mesa de coordinaci\u00f3n interinstitucional que se organizar\u00e1 por ejes, considerando un coordinador\/a por eje estrat\u00e9gico.\r\n\r\nLa elaboraci\u00f3n del diagn\u00f3stico se centra en procesos participativos liderados por equipos internos que propicien la apropiaci\u00f3n de los resultados y contempla 4 etapas. La primera etapa de autoevaluaci\u00f3n seg\u00fan eje estrat\u00e9gico se centra en el levantamiento, sistematizaci\u00f3n y an\u00e1lisis de la situaci\u00f3n interna de ambas universidades. La segunda etapa de aplicaci\u00f3n de instrumentos de recolecci\u00f3n de antecedentes, de car\u00e1cter mixto y en terreno, tiene como prop\u00f3sito indagar en las brechas, expectativas y necesidades de los actores internos y externos, con\r\nrelaci\u00f3n a la transferencia de conocimientos y tecnolog\u00edas, vinculaci\u00f3n universidad-territorio, liderazgo femenino, oferta formativa en artes, humanidades y ciencias sociales, gobernanza, ciencia y conocimientos abiertos de parte de ambas instituciones. Esta etapa se realizar\u00e1 mediante entrevistas abiertas a actores claves, talleres participativos con miembros de la comunidad y entrevistas semiestructuradas a autoridades universitarias, comunales, provinciales y regionales. En la tercera etapa, de traducci\u00f3n del diagn\u00f3stico, se realizar\u00e1 la sistematizaci\u00f3n y categorizaci\u00f3n de la informaci\u00f3n obtenida en las etapas anteriores, utilizando como metodolog\u00eda el an\u00e1lisis de texto y categorizaci\u00f3n conceptual, junto con una triangulaci\u00f3n de los datos cuantitativos y cualitativos recabados tanto internamente en cada universidad como en el medio regional del Maule y O\u0092Higgins, teniendo como resultado un informe diagn\u00f3stico a ser validado, el que incluir\u00e1 una matriz con informaci\u00f3n sistematizada por eje tem\u00e1tico y la l\u00ednea base de indicadores. La cuarta y \u00faltima etapa consiste en la validaci\u00f3n del diagn\u00f3stico, a trav\u00e9s de la presentaci\u00f3n de los resultados a una red compuesta por diversos actores: representantes de la comunidad participante, expertos nacionales e internacionales, integrantes de la\r\nmesa de coordinaci\u00f3n interinstitucional, autoridades gubernamentales y, finalmente, a instancias colegiadas y autoridades unipersonales de ambas instituciones.\r\nPosterior del diagn\u00f3stico, se realizar\u00e1 un proceso de experiencia comparada, con la idea de observar los desarrollos de los diferentes ejes en otras instituciones de educaci\u00f3n superior nacionales e internacionales. Toda esta informaci\u00f3n permitir\u00e1 avanzar a la etapa de identificaci\u00f3n de brechas para identificar, por una partes,\r\nnuestra l\u00ednea de base y por otra la distancia de nuestro desarrollo con la experiencia de otras instituciones, considerando los contextos. Finalmente, estos insumos permitir\u00e1n, que de manera participativa con la comunidad universitaria y representantes de la comunidad regional, se elabore una propuesta de plan\r\nestrat\u00e9gico, que ser\u00e1 validado con actores internos y externos; y que se convertir\u00e1 en la hoja de ruta para los\r\npr\u00f3ximos a\u00f1os.\r\n\r\nEl presente proyecto se relaciona sin\u00e9rgicamente con los proyectos en desarrollo de Ingenier\u00eda 2030 y Ciencia 2030, que se encuentran en ejecuci\u00f3n en la Universidad de Talca. Estos proyectos buscan transformar las facultades de ciencias hacia una mayor vinculaci\u00f3n con el entorno mediante la I+D+i+ebct y transformar los\r\nplanes de formaci\u00f3n para las ingenier\u00edas, siendo coherente con el objetivo propuesto para la presente convocatoria. Por otra parte, la Universidad de Talca y la Universidad de O'Higgins cuentan con diversos organismos internos que pueden potenciar el trabajo del proyecto como la Direcci\u00f3n de Innovaci\u00f3n y transferencia, la Direcci\u00f3n de\r\nInvestigaci\u00f3n, Direcci\u00f3n General de Vinculaci\u00f3n con el Medio, Direcci\u00f3n General de Aseguramiento de la Calidad y Planificaci\u00f3n, Direcci\u00f3n de G\u00e9nero en el caso de la Universidad de Talca y la Direcci\u00f3n de Investigaci\u00f3n, Direcci\u00f3n de Vinculaci\u00f3n y Transferencia, Direcci\u00f3n de Postgrado, Direcci\u00f3n de Comunicaciones, Direcci\u00f3n de\r\nInternacionalizaci\u00f3n y Direcci\u00f3n de Equidad de G\u00e9nero y Diversidades en el caso de la Universidad de O'Higgins. Por \u00faltimo, la Universidad de Talca se encuentra desarrollando diferentes proyectos como Proyecto InES Redit,\r\nProyecto InES G\u00e9nero, Proyecto InEs I+D, Proyecto Ciencia Abierta, que buscan consolidar un modelo de gesti\u00f3n de la innovaci\u00f3n y emprendimiento basado en I+D interdisciplinario y transdisciplinario con perspectiva de g\u00e9nero, por una parte; as\u00ed como fortalecer y consolidar las capacidades institucionales actuales de soporte al\r\nproceso de innovaci\u00f3n basada en I+D por otra.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> CON203020019<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2023 - Septiembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26499\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Consorcio del Valle Central de Chile: una propuesta territorial,  regional y estatal para la innovaci\u00f3n, desarrollo y fortalecimiento de las artes, humanidades y ciencias sociales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26499\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26499\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las regiones de O\u0092Higgins y el Maule tienen una historia com\u00fan, caracter\u00edsticas y un desarrollo similar. Ambas regiones, ubicadas en el Valle Central chileno, comparten elementos culturales, s\u00edmbolos, historias, personajes y personas. Estas dos regiones, caracterizadas por una fuerte componente agr\u00edcola, han vivido la migraci\u00f3n rural-urbana y la transformaci\u00f3n del mundo agr\u00edcola en distintas componentes. Debido a las importantes similitudes territoriales, humanas y productivas que poseen las regiones de O\u0092Higgins y el Maule, es que las universidades estatales de ambos territorios proponen un trabajo consorciado de fortalecimiento de las artes, humanidades y ciencias sociales. Su objetivo es crear un plan de desarrollo (estrat\u00e9gico y de implementaci\u00f3n) de corto, mediano y largo plazo para el fortalecimiento de las Artes, Humanidades y Ciencias Sociales en las unidades postulantes de las Universidades de Talca y O\u0092Higgins, incorporando inter-transdisciplina (I-TD) y sinergia interuniversitaria (S-IU), que permita transformar de manera innovadora procesos acad\u00e9micos de gesti\u00f3n y gobernanza,\r\nformaci\u00f3n de pre y postgrado, generaci\u00f3n y transferencia de nuevo conocimiento, creaci\u00f3n y tecnolog\u00eda, v\u00ednculo territorial bidireccional con el medio que las cobija y, promover transversalmente la equidad de g\u00e9nero y el liderazgo femenino, los derechos humanos, el patrimonio cultural, la salud mental y el bienestar psicol\u00f3gico,\r\npara as\u00ed aportar conjuntamente a las necesidades regionales y al logro de una mejor calidad de vida de los actuales y futuros habitantes de sus comunidades.\r\n\r\nTanto la Universidad de Talca como la Universidad de O\u0092Higgins tiene capacidades instaladas en estas \u00e1reas con distintos niveles desarrollo. En el caso de la  Universidad de Talca, las unidades acad\u00e9micas pertinentes a este concurso son las Facultades de: Psicolog\u00eda, Ciencias Jur\u00eddicas y Ciencias Sociales, Arquitectura, M\u00fasica y Dise\u00f1o; y el Instituto de Humanidades Abate Molina. En el caso de la Universidad de O\u0092Higgins las unidades acad\u00e9micas relevantes son el Instituto de Ciencias Sociales, la Escuela de Ciencias Sociales y el Instituto de Altos Estudios\r\nAudiovisuales.\r\n\r\nPara el desarrollo del proyecto, adem\u00e1s del trabajo de los directores, se realizar\u00e1 la contrataci\u00f3n de profesionales para tareas de gesti\u00f3n y planificaci\u00f3n del proyecto. Las autoridades de ambas universidades (rectores, vicerrectores, decanos\/as, entre otros) interactuar\u00e1n con el equipo mediante un consejo estrat\u00e9gico. Adem\u00e1s,\r\nse conformar\u00e1 una mesa de coordinaci\u00f3n interinstitucional que se organizar\u00e1 por ejes, considerando un coordinador\/a por eje estrat\u00e9gico.\r\n\r\nLa elaboraci\u00f3n del diagn\u00f3stico se centra en procesos participativos liderados por equipos internos que propicien la apropiaci\u00f3n de los resultados y contempla 4 etapas. La primera etapa de autoevaluaci\u00f3n seg\u00fan eje estrat\u00e9gico se centra en el levantamiento, sistematizaci\u00f3n y an\u00e1lisis de la situaci\u00f3n interna de ambas universidades. La segunda etapa de aplicaci\u00f3n de instrumentos de recolecci\u00f3n de antecedentes, de car\u00e1cter mixto y en terreno, tiene como prop\u00f3sito indagar en las brechas, expectativas y necesidades de los actores internos y externos, con\r\nrelaci\u00f3n a la transferencia de conocimientos y tecnolog\u00edas, vinculaci\u00f3n universidad-territorio, liderazgo femenino, oferta formativa en artes, humanidades y ciencias sociales, gobernanza, ciencia y conocimientos abiertos de parte de ambas instituciones. Esta etapa se realizar\u00e1 mediante entrevistas abiertas a actores claves, talleres participativos con miembros de la comunidad y entrevistas semiestructuradas a autoridades universitarias, comunales, provinciales y regionales. En la tercera etapa, de traducci\u00f3n del diagn\u00f3stico, se realizar\u00e1 la sistematizaci\u00f3n y categorizaci\u00f3n de la informaci\u00f3n obtenida en las etapas anteriores, utilizando como metodolog\u00eda el an\u00e1lisis de texto y categorizaci\u00f3n conceptual, junto con una triangulaci\u00f3n de los datos cuantitativos y cualitativos recabados tanto internamente en cada universidad como en el medio regional del Maule y O\u0092Higgins, teniendo como resultado un informe diagn\u00f3stico a ser validado, el que incluir\u00e1 una matriz con informaci\u00f3n sistematizada por eje tem\u00e1tico y la l\u00ednea base de indicadores. La cuarta y \u00faltima etapa consiste en la validaci\u00f3n del diagn\u00f3stico, a trav\u00e9s de la presentaci\u00f3n de los resultados a una red compuesta por diversos actores: representantes de la comunidad participante, expertos nacionales e internacionales, integrantes de la\r\nmesa de coordinaci\u00f3n interinstitucional, autoridades gubernamentales y, finalmente, a instancias colegiadas y autoridades unipersonales de ambas instituciones.\r\nPosterior del diagn\u00f3stico, se realizar\u00e1 un proceso de experiencia comparada, con la idea de observar los desarrollos de los diferentes ejes en otras instituciones de educaci\u00f3n superior nacionales e internacionales. Toda esta informaci\u00f3n permitir\u00e1 avanzar a la etapa de identificaci\u00f3n de brechas para identificar, por una partes,\r\nnuestra l\u00ednea de base y por otra la distancia de nuestro desarrollo con la experiencia de otras instituciones, considerando los contextos. Finalmente, estos insumos permitir\u00e1n, que de manera participativa con la comunidad universitaria y representantes de la comunidad regional, se elabore una propuesta de plan\r\nestrat\u00e9gico, que ser\u00e1 validado con actores internos y externos; y que se convertir\u00e1 en la hoja de ruta para los\r\npr\u00f3ximos a\u00f1os.\r\n\r\nEl presente proyecto se relaciona sin\u00e9rgicamente con los proyectos en desarrollo de Ingenier\u00eda 2030 y Ciencia 2030, que se encuentran en ejecuci\u00f3n en la Universidad de Talca. Estos proyectos buscan transformar las facultades de ciencias hacia una mayor vinculaci\u00f3n con el entorno mediante la I+D+i+ebct y transformar los\r\nplanes de formaci\u00f3n para las ingenier\u00edas, siendo coherente con el objetivo propuesto para la presente convocatoria. Por otra parte, la Universidad de Talca y la Universidad de O'Higgins cuentan con diversos organismos internos que pueden potenciar el trabajo del proyecto como la Direcci\u00f3n de Innovaci\u00f3n y transferencia, la Direcci\u00f3n de\r\nInvestigaci\u00f3n, Direcci\u00f3n General de Vinculaci\u00f3n con el Medio, Direcci\u00f3n General de Aseguramiento de la Calidad y Planificaci\u00f3n, Direcci\u00f3n de G\u00e9nero en el caso de la Universidad de Talca y la Direcci\u00f3n de Investigaci\u00f3n, Direcci\u00f3n de Vinculaci\u00f3n y Transferencia, Direcci\u00f3n de Postgrado, Direcci\u00f3n de Comunicaciones, Direcci\u00f3n de\r\nInternacionalizaci\u00f3n y Direcci\u00f3n de Equidad de G\u00e9nero y Diversidades en el caso de la Universidad de O'Higgins. Por \u00faltimo, la Universidad de Talca se encuentra desarrollando diferentes proyectos como Proyecto InES Redit,\r\nProyecto InES G\u00e9nero, Proyecto InEs I+D, Proyecto Ciencia Abierta, que buscan consolidar un modelo de gesti\u00f3n de la innovaci\u00f3n y emprendimiento basado en I+D interdisciplinario y transdisciplinario con perspectiva de g\u00e9nero, por una parte; as\u00ed como fortalecer y consolidar las capacidades institucionales actuales de soporte al\r\nproceso de innovaci\u00f3n basada en I+D por otra.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> CON203020019<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2023 - Septiembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26544\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Consorcio del Valle Central de Chile: una propuesta territorial,  regional y estatal para la innovaci\u00f3n, desarrollo y fortalecimiento de las artes, humanidades y ciencias sociales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26544\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26544\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las regiones de O\u0092Higgins y el Maule tienen una historia com\u00fan, caracter\u00edsticas y un desarrollo similar. Ambas regiones, ubicadas en el Valle Central chileno, comparten elementos culturales, s\u00edmbolos, historias, personajes y personas. Estas dos regiones, caracterizadas por una fuerte componente agr\u00edcola, han vivido la migraci\u00f3n rural-urbana y la transformaci\u00f3n del mundo agr\u00edcola en distintas componentes. Debido a las importantes similitudes territoriales, humanas y productivas que poseen las regiones de O\u0092Higgins y el Maule, es que las universidades estatales de ambos territorios proponen un trabajo consorciado de fortalecimiento de las artes, humanidades y ciencias sociales. Su objetivo es crear un plan de desarrollo (estrat\u00e9gico y de implementaci\u00f3n) de corto, mediano y largo plazo para el fortalecimiento de las Artes, Humanidades y Ciencias Sociales en las unidades postulantes de las Universidades de Talca y O\u0092Higgins, incorporando inter-transdisciplina (I-TD) y sinergia interuniversitaria (S-IU), que permita transformar de manera innovadora procesos acad\u00e9micos de gesti\u00f3n y gobernanza,\r\nformaci\u00f3n de pre y postgrado, generaci\u00f3n y transferencia de nuevo conocimiento, creaci\u00f3n y tecnolog\u00eda, v\u00ednculo territorial bidireccional con el medio que las cobija y, promover transversalmente la equidad de g\u00e9nero y el liderazgo femenino, los derechos humanos, el patrimonio cultural, la salud mental y el bienestar psicol\u00f3gico,\r\npara as\u00ed aportar conjuntamente a las necesidades regionales y al logro de una mejor calidad de vida de los actuales y futuros habitantes de sus comunidades.\r\n\r\nTanto la Universidad de Talca como la Universidad de O\u0092Higgins tiene capacidades instaladas en estas \u00e1reas con distintos niveles desarrollo. En el caso de la  Universidad de Talca, las unidades acad\u00e9micas pertinentes a este concurso son las Facultades de: Psicolog\u00eda, Ciencias Jur\u00eddicas y Ciencias Sociales, Arquitectura, M\u00fasica y Dise\u00f1o; y el Instituto de Humanidades Abate Molina. En el caso de la Universidad de O\u0092Higgins las unidades acad\u00e9micas relevantes son el Instituto de Ciencias Sociales, la Escuela de Ciencias Sociales y el Instituto de Altos Estudios\r\nAudiovisuales.\r\n\r\nPara el desarrollo del proyecto, adem\u00e1s del trabajo de los directores, se realizar\u00e1 la contrataci\u00f3n de profesionales para tareas de gesti\u00f3n y planificaci\u00f3n del proyecto. Las autoridades de ambas universidades (rectores, vicerrectores, decanos\/as, entre otros) interactuar\u00e1n con el equipo mediante un consejo estrat\u00e9gico. Adem\u00e1s,\r\nse conformar\u00e1 una mesa de coordinaci\u00f3n interinstitucional que se organizar\u00e1 por ejes, considerando un coordinador\/a por eje estrat\u00e9gico.\r\n\r\nLa elaboraci\u00f3n del diagn\u00f3stico se centra en procesos participativos liderados por equipos internos que propicien la apropiaci\u00f3n de los resultados y contempla 4 etapas. La primera etapa de autoevaluaci\u00f3n seg\u00fan eje estrat\u00e9gico se centra en el levantamiento, sistematizaci\u00f3n y an\u00e1lisis de la situaci\u00f3n interna de ambas universidades. La segunda etapa de aplicaci\u00f3n de instrumentos de recolecci\u00f3n de antecedentes, de car\u00e1cter mixto y en terreno, tiene como prop\u00f3sito indagar en las brechas, expectativas y necesidades de los actores internos y externos, con\r\nrelaci\u00f3n a la transferencia de conocimientos y tecnolog\u00edas, vinculaci\u00f3n universidad-territorio, liderazgo femenino, oferta formativa en artes, humanidades y ciencias sociales, gobernanza, ciencia y conocimientos abiertos de parte de ambas instituciones. Esta etapa se realizar\u00e1 mediante entrevistas abiertas a actores claves, talleres participativos con miembros de la comunidad y entrevistas semiestructuradas a autoridades universitarias, comunales, provinciales y regionales. En la tercera etapa, de traducci\u00f3n del diagn\u00f3stico, se realizar\u00e1 la sistematizaci\u00f3n y categorizaci\u00f3n de la informaci\u00f3n obtenida en las etapas anteriores, utilizando como metodolog\u00eda el an\u00e1lisis de texto y categorizaci\u00f3n conceptual, junto con una triangulaci\u00f3n de los datos cuantitativos y cualitativos recabados tanto internamente en cada universidad como en el medio regional del Maule y O\u0092Higgins, teniendo como resultado un informe diagn\u00f3stico a ser validado, el que incluir\u00e1 una matriz con informaci\u00f3n sistematizada por eje tem\u00e1tico y la l\u00ednea base de indicadores. La cuarta y \u00faltima etapa consiste en la validaci\u00f3n del diagn\u00f3stico, a trav\u00e9s de la presentaci\u00f3n de los resultados a una red compuesta por diversos actores: representantes de la comunidad participante, expertos nacionales e internacionales, integrantes de la\r\nmesa de coordinaci\u00f3n interinstitucional, autoridades gubernamentales y, finalmente, a instancias colegiadas y autoridades unipersonales de ambas instituciones.\r\nPosterior del diagn\u00f3stico, se realizar\u00e1 un proceso de experiencia comparada, con la idea de observar los desarrollos de los diferentes ejes en otras instituciones de educaci\u00f3n superior nacionales e internacionales. Toda esta informaci\u00f3n permitir\u00e1 avanzar a la etapa de identificaci\u00f3n de brechas para identificar, por una partes,\r\nnuestra l\u00ednea de base y por otra la distancia de nuestro desarrollo con la experiencia de otras instituciones, considerando los contextos. Finalmente, estos insumos permitir\u00e1n, que de manera participativa con la comunidad universitaria y representantes de la comunidad regional, se elabore una propuesta de plan\r\nestrat\u00e9gico, que ser\u00e1 validado con actores internos y externos; y que se convertir\u00e1 en la hoja de ruta para los\r\npr\u00f3ximos a\u00f1os.\r\n\r\nEl presente proyecto se relaciona sin\u00e9rgicamente con los proyectos en desarrollo de Ingenier\u00eda 2030 y Ciencia 2030, que se encuentran en ejecuci\u00f3n en la Universidad de Talca. Estos proyectos buscan transformar las facultades de ciencias hacia una mayor vinculaci\u00f3n con el entorno mediante la I+D+i+ebct y transformar los\r\nplanes de formaci\u00f3n para las ingenier\u00edas, siendo coherente con el objetivo propuesto para la presente convocatoria. Por otra parte, la Universidad de Talca y la Universidad de O'Higgins cuentan con diversos organismos internos que pueden potenciar el trabajo del proyecto como la Direcci\u00f3n de Innovaci\u00f3n y transferencia, la Direcci\u00f3n de\r\nInvestigaci\u00f3n, Direcci\u00f3n General de Vinculaci\u00f3n con el Medio, Direcci\u00f3n General de Aseguramiento de la Calidad y Planificaci\u00f3n, Direcci\u00f3n de G\u00e9nero en el caso de la Universidad de Talca y la Direcci\u00f3n de Investigaci\u00f3n, Direcci\u00f3n de Vinculaci\u00f3n y Transferencia, Direcci\u00f3n de Postgrado, Direcci\u00f3n de Comunicaciones, Direcci\u00f3n de\r\nInternacionalizaci\u00f3n y Direcci\u00f3n de Equidad de G\u00e9nero y Diversidades en el caso de la Universidad de O'Higgins. Por \u00faltimo, la Universidad de Talca se encuentra desarrollando diferentes proyectos como Proyecto InES Redit,\r\nProyecto InES G\u00e9nero, Proyecto InEs I+D, Proyecto Ciencia Abierta, que buscan consolidar un modelo de gesti\u00f3n de la innovaci\u00f3n y emprendimiento basado en I+D interdisciplinario y transdisciplinario con perspectiva de g\u00e9nero, por una parte; as\u00ed como fortalecer y consolidar las capacidades institucionales actuales de soporte al\r\nproceso de innovaci\u00f3n basada en I+D por otra.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Clientes (Instituciones Educativas)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26702\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26702\" aria-expanded=\"false\" aria-controls=\"collapse-26702\">\n                                            PILOTAJE DE UNA ESTRATEGIA DE TRANSFERENCIA DE LAS TECNOLOG\u00cdAS EDUCATIVAS\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26702\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26702\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Mediante proyectos FONDEF adjudicados y ejecutados se desarroll\u00f3 una metodolog\u00eda de ense\u00f1anza para las matem\u00e1ticas tempranas basada en dos tecnolog\u00edas, las cuales son evaluaciones digitales basadas en juegos y materiales de ense\u00f1anza en formatos de juegos de mesa (ver https:\/\/www.jugarmate.org). El proyecto finaliz\u00f3 exitosamente pudiendo validar la efectividad de los materiales de ense\u00f1anza y que las evaluaciones digitales tienen propiedades psicom\u00e9tricas adecuadas para ser usado como instrumento de evaluaci\u00f3n.\r\nLa literatura es enf\u00e1tica en cuanto a la ineficacia de los programas de capacitaci\u00f3n docente ya que no tienen efecto en la mejora de los aprendizajes de los estudiantes (Yoshikawa et al., 2015). Con base en tendencias internacionales de emprendimiento innovador, un modelo m\u00e1s adecuado para realizar la transferencia tecnol\u00f3gica deber\u00eda basarse en un modelo de negocios que permita (1) ofrecer servicios complementarios que potencien el valor percibido por el usuario, (2) capturar el valor efectivo que se ofrece a los usuarios de manera sustentable y (3) masificar el uso de las tecnolog\u00edas desarrolladas. Un modelo con estas caracter\u00edsticas facilitar\u00eda que la universidad realice vinculaci\u00f3n con el medio desde el trabajo de investigaci\u00f3n y desarrollo que se ha realizado dentro de la Universidad, demostrando as\u00ed resultados expl\u00edcitos en la comunidad educativa. \r\n\r\nMediante este proyecto queremos pilotear un modelo de transferencia tecnol\u00f3gica que permita a los establecimientos educacionales acceder a estas tecnolog\u00edas en forma de servicios educativos. El modelo de transferencia se basa en crear un paquete tecnol\u00f3gico para habilitar a ciertos distribuidores de tecnolog\u00eda educativa (p.ej., fundaciones y empresas educativas, editoriales, etc.) de manera que brinden el servicio de gesti\u00f3n pedag\u00f3gica del aula matem\u00e1tica usando las tecnolog\u00edas educativas desarrolladas. De esta manera, el Laboratorio de Aprendizaje Matem\u00e1tico (LAM) brindar\u00e1 servicios a estos distribuidores los cuales los habilitar\u00e1n para que brinden servicios a los establecimientos educativos. Este modelo permite enriquecer las tecnolog\u00edas educativas con servicios complementarios (tales como evaluaci\u00f3n, acompa\u00f1amiento, intervenci\u00f3n de aula, etc.), permite capturar valor de manera sustentable debido a que se entrega como un servicio y el escalamiento y masificaci\u00f3n tecnol\u00f3gica se puede lograr a trav\u00e9s de llegar a acuerdos con un mayor n\u00famero de distribuidores tecnol\u00f3gicos.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> CON203020019<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2023 - Septiembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26758\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Consorcio del Valle Central de Chile: una propuesta territorial,  regional y estatal para la innovaci\u00f3n, desarrollo y fortalecimiento de las artes, humanidades y ciencias sociales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26758\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26758\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las regiones de O\u0092Higgins y el Maule tienen una historia com\u00fan, caracter\u00edsticas y un desarrollo similar. Ambas regiones, ubicadas en el Valle Central chileno, comparten elementos culturales, s\u00edmbolos, historias, personajes y personas. Estas dos regiones, caracterizadas por una fuerte componente agr\u00edcola, han vivido la migraci\u00f3n rural-urbana y la transformaci\u00f3n del mundo agr\u00edcola en distintas componentes. Debido a las importantes similitudes territoriales, humanas y productivas que poseen las regiones de O\u0092Higgins y el Maule, es que las universidades estatales de ambos territorios proponen un trabajo consorciado de fortalecimiento de las artes, humanidades y ciencias sociales. Su objetivo es crear un plan de desarrollo (estrat\u00e9gico y de implementaci\u00f3n) de corto, mediano y largo plazo para el fortalecimiento de las Artes, Humanidades y Ciencias Sociales en las unidades postulantes de las Universidades de Talca y O\u0092Higgins, incorporando inter-transdisciplina (I-TD) y sinergia interuniversitaria (S-IU), que permita transformar de manera innovadora procesos acad\u00e9micos de gesti\u00f3n y gobernanza,\r\nformaci\u00f3n de pre y postgrado, generaci\u00f3n y transferencia de nuevo conocimiento, creaci\u00f3n y tecnolog\u00eda, v\u00ednculo territorial bidireccional con el medio que las cobija y, promover transversalmente la equidad de g\u00e9nero y el liderazgo femenino, los derechos humanos, el patrimonio cultural, la salud mental y el bienestar psicol\u00f3gico,\r\npara as\u00ed aportar conjuntamente a las necesidades regionales y al logro de una mejor calidad de vida de los actuales y futuros habitantes de sus comunidades.\r\n\r\nTanto la Universidad de Talca como la Universidad de O\u0092Higgins tiene capacidades instaladas en estas \u00e1reas con distintos niveles desarrollo. En el caso de la  Universidad de Talca, las unidades acad\u00e9micas pertinentes a este concurso son las Facultades de: Psicolog\u00eda, Ciencias Jur\u00eddicas y Ciencias Sociales, Arquitectura, M\u00fasica y Dise\u00f1o; y el Instituto de Humanidades Abate Molina. En el caso de la Universidad de O\u0092Higgins las unidades acad\u00e9micas relevantes son el Instituto de Ciencias Sociales, la Escuela de Ciencias Sociales y el Instituto de Altos Estudios\r\nAudiovisuales.\r\n\r\nPara el desarrollo del proyecto, adem\u00e1s del trabajo de los directores, se realizar\u00e1 la contrataci\u00f3n de profesionales para tareas de gesti\u00f3n y planificaci\u00f3n del proyecto. Las autoridades de ambas universidades (rectores, vicerrectores, decanos\/as, entre otros) interactuar\u00e1n con el equipo mediante un consejo estrat\u00e9gico. Adem\u00e1s,\r\nse conformar\u00e1 una mesa de coordinaci\u00f3n interinstitucional que se organizar\u00e1 por ejes, considerando un coordinador\/a por eje estrat\u00e9gico.\r\n\r\nLa elaboraci\u00f3n del diagn\u00f3stico se centra en procesos participativos liderados por equipos internos que propicien la apropiaci\u00f3n de los resultados y contempla 4 etapas. La primera etapa de autoevaluaci\u00f3n seg\u00fan eje estrat\u00e9gico se centra en el levantamiento, sistematizaci\u00f3n y an\u00e1lisis de la situaci\u00f3n interna de ambas universidades. La segunda etapa de aplicaci\u00f3n de instrumentos de recolecci\u00f3n de antecedentes, de car\u00e1cter mixto y en terreno, tiene como prop\u00f3sito indagar en las brechas, expectativas y necesidades de los actores internos y externos, con\r\nrelaci\u00f3n a la transferencia de conocimientos y tecnolog\u00edas, vinculaci\u00f3n universidad-territorio, liderazgo femenino, oferta formativa en artes, humanidades y ciencias sociales, gobernanza, ciencia y conocimientos abiertos de parte de ambas instituciones. Esta etapa se realizar\u00e1 mediante entrevistas abiertas a actores claves, talleres participativos con miembros de la comunidad y entrevistas semiestructuradas a autoridades universitarias, comunales, provinciales y regionales. En la tercera etapa, de traducci\u00f3n del diagn\u00f3stico, se realizar\u00e1 la sistematizaci\u00f3n y categorizaci\u00f3n de la informaci\u00f3n obtenida en las etapas anteriores, utilizando como metodolog\u00eda el an\u00e1lisis de texto y categorizaci\u00f3n conceptual, junto con una triangulaci\u00f3n de los datos cuantitativos y cualitativos recabados tanto internamente en cada universidad como en el medio regional del Maule y O\u0092Higgins, teniendo como resultado un informe diagn\u00f3stico a ser validado, el que incluir\u00e1 una matriz con informaci\u00f3n sistematizada por eje tem\u00e1tico y la l\u00ednea base de indicadores. La cuarta y \u00faltima etapa consiste en la validaci\u00f3n del diagn\u00f3stico, a trav\u00e9s de la presentaci\u00f3n de los resultados a una red compuesta por diversos actores: representantes de la comunidad participante, expertos nacionales e internacionales, integrantes de la\r\nmesa de coordinaci\u00f3n interinstitucional, autoridades gubernamentales y, finalmente, a instancias colegiadas y autoridades unipersonales de ambas instituciones.\r\nPosterior del diagn\u00f3stico, se realizar\u00e1 un proceso de experiencia comparada, con la idea de observar los desarrollos de los diferentes ejes en otras instituciones de educaci\u00f3n superior nacionales e internacionales. Toda esta informaci\u00f3n permitir\u00e1 avanzar a la etapa de identificaci\u00f3n de brechas para identificar, por una partes,\r\nnuestra l\u00ednea de base y por otra la distancia de nuestro desarrollo con la experiencia de otras instituciones, considerando los contextos. Finalmente, estos insumos permitir\u00e1n, que de manera participativa con la comunidad universitaria y representantes de la comunidad regional, se elabore una propuesta de plan\r\nestrat\u00e9gico, que ser\u00e1 validado con actores internos y externos; y que se convertir\u00e1 en la hoja de ruta para los\r\npr\u00f3ximos a\u00f1os.\r\n\r\nEl presente proyecto se relaciona sin\u00e9rgicamente con los proyectos en desarrollo de Ingenier\u00eda 2030 y Ciencia 2030, que se encuentran en ejecuci\u00f3n en la Universidad de Talca. Estos proyectos buscan transformar las facultades de ciencias hacia una mayor vinculaci\u00f3n con el entorno mediante la I+D+i+ebct y transformar los\r\nplanes de formaci\u00f3n para las ingenier\u00edas, siendo coherente con el objetivo propuesto para la presente convocatoria. Por otra parte, la Universidad de Talca y la Universidad de O'Higgins cuentan con diversos organismos internos que pueden potenciar el trabajo del proyecto como la Direcci\u00f3n de Innovaci\u00f3n y transferencia, la Direcci\u00f3n de\r\nInvestigaci\u00f3n, Direcci\u00f3n General de Vinculaci\u00f3n con el Medio, Direcci\u00f3n General de Aseguramiento de la Calidad y Planificaci\u00f3n, Direcci\u00f3n de G\u00e9nero en el caso de la Universidad de Talca y la Direcci\u00f3n de Investigaci\u00f3n, Direcci\u00f3n de Vinculaci\u00f3n y Transferencia, Direcci\u00f3n de Postgrado, Direcci\u00f3n de Comunicaciones, Direcci\u00f3n de\r\nInternacionalizaci\u00f3n y Direcci\u00f3n de Equidad de G\u00e9nero y Diversidades en el caso de la Universidad de O'Higgins. Por \u00faltimo, la Universidad de Talca se encuentra desarrollando diferentes proyectos como Proyecto InES Redit,\r\nProyecto InES G\u00e9nero, Proyecto InEs I+D, Proyecto Ciencia Abierta, que buscan consolidar un modelo de gesti\u00f3n de la innovaci\u00f3n y emprendimiento basado en I+D interdisciplinario y transdisciplinario con perspectiva de g\u00e9nero, por una parte; as\u00ed como fortalecer y consolidar las capacidades institucionales actuales de soporte al\r\nproceso de innovaci\u00f3n basada en I+D por otra.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> CON203020019<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2023 - Septiembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26913\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Consorcio del Valle Central de Chile: una propuesta territorial,  regional y estatal para la innovaci\u00f3n, desarrollo y fortalecimiento de las artes, humanidades y ciencias sociales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26913\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26913\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las regiones de O\u0092Higgins y el Maule tienen una historia com\u00fan, caracter\u00edsticas y un desarrollo similar. Ambas regiones, ubicadas en el Valle Central chileno, comparten elementos culturales, s\u00edmbolos, historias, personajes y personas. Estas dos regiones, caracterizadas por una fuerte componente agr\u00edcola, han vivido la migraci\u00f3n rural-urbana y la transformaci\u00f3n del mundo agr\u00edcola en distintas componentes. Debido a las importantes similitudes territoriales, humanas y productivas que poseen las regiones de O\u0092Higgins y el Maule, es que las universidades estatales de ambos territorios proponen un trabajo consorciado de fortalecimiento de las artes, humanidades y ciencias sociales. Su objetivo es crear un plan de desarrollo (estrat\u00e9gico y de implementaci\u00f3n) de corto, mediano y largo plazo para el fortalecimiento de las Artes, Humanidades y Ciencias Sociales en las unidades postulantes de las Universidades de Talca y O\u0092Higgins, incorporando inter-transdisciplina (I-TD) y sinergia interuniversitaria (S-IU), que permita transformar de manera innovadora procesos acad\u00e9micos de gesti\u00f3n y gobernanza,\r\nformaci\u00f3n de pre y postgrado, generaci\u00f3n y transferencia de nuevo conocimiento, creaci\u00f3n y tecnolog\u00eda, v\u00ednculo territorial bidireccional con el medio que las cobija y, promover transversalmente la equidad de g\u00e9nero y el liderazgo femenino, los derechos humanos, el patrimonio cultural, la salud mental y el bienestar psicol\u00f3gico,\r\npara as\u00ed aportar conjuntamente a las necesidades regionales y al logro de una mejor calidad de vida de los actuales y futuros habitantes de sus comunidades.\r\n\r\nTanto la Universidad de Talca como la Universidad de O\u0092Higgins tiene capacidades instaladas en estas \u00e1reas con distintos niveles desarrollo. En el caso de la  Universidad de Talca, las unidades acad\u00e9micas pertinentes a este concurso son las Facultades de: Psicolog\u00eda, Ciencias Jur\u00eddicas y Ciencias Sociales, Arquitectura, M\u00fasica y Dise\u00f1o; y el Instituto de Humanidades Abate Molina. En el caso de la Universidad de O\u0092Higgins las unidades acad\u00e9micas relevantes son el Instituto de Ciencias Sociales, la Escuela de Ciencias Sociales y el Instituto de Altos Estudios\r\nAudiovisuales.\r\n\r\nPara el desarrollo del proyecto, adem\u00e1s del trabajo de los directores, se realizar\u00e1 la contrataci\u00f3n de profesionales para tareas de gesti\u00f3n y planificaci\u00f3n del proyecto. Las autoridades de ambas universidades (rectores, vicerrectores, decanos\/as, entre otros) interactuar\u00e1n con el equipo mediante un consejo estrat\u00e9gico. Adem\u00e1s,\r\nse conformar\u00e1 una mesa de coordinaci\u00f3n interinstitucional que se organizar\u00e1 por ejes, considerando un coordinador\/a por eje estrat\u00e9gico.\r\n\r\nLa elaboraci\u00f3n del diagn\u00f3stico se centra en procesos participativos liderados por equipos internos que propicien la apropiaci\u00f3n de los resultados y contempla 4 etapas. La primera etapa de autoevaluaci\u00f3n seg\u00fan eje estrat\u00e9gico se centra en el levantamiento, sistematizaci\u00f3n y an\u00e1lisis de la situaci\u00f3n interna de ambas universidades. La segunda etapa de aplicaci\u00f3n de instrumentos de recolecci\u00f3n de antecedentes, de car\u00e1cter mixto y en terreno, tiene como prop\u00f3sito indagar en las brechas, expectativas y necesidades de los actores internos y externos, con\r\nrelaci\u00f3n a la transferencia de conocimientos y tecnolog\u00edas, vinculaci\u00f3n universidad-territorio, liderazgo femenino, oferta formativa en artes, humanidades y ciencias sociales, gobernanza, ciencia y conocimientos abiertos de parte de ambas instituciones. Esta etapa se realizar\u00e1 mediante entrevistas abiertas a actores claves, talleres participativos con miembros de la comunidad y entrevistas semiestructuradas a autoridades universitarias, comunales, provinciales y regionales. En la tercera etapa, de traducci\u00f3n del diagn\u00f3stico, se realizar\u00e1 la sistematizaci\u00f3n y categorizaci\u00f3n de la informaci\u00f3n obtenida en las etapas anteriores, utilizando como metodolog\u00eda el an\u00e1lisis de texto y categorizaci\u00f3n conceptual, junto con una triangulaci\u00f3n de los datos cuantitativos y cualitativos recabados tanto internamente en cada universidad como en el medio regional del Maule y O\u0092Higgins, teniendo como resultado un informe diagn\u00f3stico a ser validado, el que incluir\u00e1 una matriz con informaci\u00f3n sistematizada por eje tem\u00e1tico y la l\u00ednea base de indicadores. La cuarta y \u00faltima etapa consiste en la validaci\u00f3n del diagn\u00f3stico, a trav\u00e9s de la presentaci\u00f3n de los resultados a una red compuesta por diversos actores: representantes de la comunidad participante, expertos nacionales e internacionales, integrantes de la\r\nmesa de coordinaci\u00f3n interinstitucional, autoridades gubernamentales y, finalmente, a instancias colegiadas y autoridades unipersonales de ambas instituciones.\r\nPosterior del diagn\u00f3stico, se realizar\u00e1 un proceso de experiencia comparada, con la idea de observar los desarrollos de los diferentes ejes en otras instituciones de educaci\u00f3n superior nacionales e internacionales. Toda esta informaci\u00f3n permitir\u00e1 avanzar a la etapa de identificaci\u00f3n de brechas para identificar, por una partes,\r\nnuestra l\u00ednea de base y por otra la distancia de nuestro desarrollo con la experiencia de otras instituciones, considerando los contextos. Finalmente, estos insumos permitir\u00e1n, que de manera participativa con la comunidad universitaria y representantes de la comunidad regional, se elabore una propuesta de plan\r\nestrat\u00e9gico, que ser\u00e1 validado con actores internos y externos; y que se convertir\u00e1 en la hoja de ruta para los\r\npr\u00f3ximos a\u00f1os.\r\n\r\nEl presente proyecto se relaciona sin\u00e9rgicamente con los proyectos en desarrollo de Ingenier\u00eda 2030 y Ciencia 2030, que se encuentran en ejecuci\u00f3n en la Universidad de Talca. Estos proyectos buscan transformar las facultades de ciencias hacia una mayor vinculaci\u00f3n con el entorno mediante la I+D+i+ebct y transformar los\r\nplanes de formaci\u00f3n para las ingenier\u00edas, siendo coherente con el objetivo propuesto para la presente convocatoria. Por otra parte, la Universidad de Talca y la Universidad de O'Higgins cuentan con diversos organismos internos que pueden potenciar el trabajo del proyecto como la Direcci\u00f3n de Innovaci\u00f3n y transferencia, la Direcci\u00f3n de\r\nInvestigaci\u00f3n, Direcci\u00f3n General de Vinculaci\u00f3n con el Medio, Direcci\u00f3n General de Aseguramiento de la Calidad y Planificaci\u00f3n, Direcci\u00f3n de G\u00e9nero en el caso de la Universidad de Talca y la Direcci\u00f3n de Investigaci\u00f3n, Direcci\u00f3n de Vinculaci\u00f3n y Transferencia, Direcci\u00f3n de Postgrado, Direcci\u00f3n de Comunicaciones, Direcci\u00f3n de\r\nInternacionalizaci\u00f3n y Direcci\u00f3n de Equidad de G\u00e9nero y Diversidades en el caso de la Universidad de O'Higgins. Por \u00faltimo, la Universidad de Talca se encuentra desarrollando diferentes proyectos como Proyecto InES Redit,\r\nProyecto InES G\u00e9nero, Proyecto InEs I+D, Proyecto Ciencia Abierta, que buscan consolidar un modelo de gesti\u00f3n de la innovaci\u00f3n y emprendimiento basado en I+D interdisciplinario y transdisciplinario con perspectiva de g\u00e9nero, por una parte; as\u00ed como fortalecer y consolidar las capacidades institucionales actuales de soporte al\r\nproceso de innovaci\u00f3n basada en I+D por otra.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> CON203020019<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2023 - Septiembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26992\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Consorcio del Valle Central de Chile: una propuesta territorial,  regional y estatal para la innovaci\u00f3n, desarrollo y fortalecimiento de las artes, humanidades y ciencias sociales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26992\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26992\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las regiones de O\u0092Higgins y el Maule tienen una historia com\u00fan, caracter\u00edsticas y un desarrollo similar. Ambas regiones, ubicadas en el Valle Central chileno, comparten elementos culturales, s\u00edmbolos, historias, personajes y personas. Estas dos regiones, caracterizadas por una fuerte componente agr\u00edcola, han vivido la migraci\u00f3n rural-urbana y la transformaci\u00f3n del mundo agr\u00edcola en distintas componentes. Debido a las importantes similitudes territoriales, humanas y productivas que poseen las regiones de O\u0092Higgins y el Maule, es que las universidades estatales de ambos territorios proponen un trabajo consorciado de fortalecimiento de las artes, humanidades y ciencias sociales. Su objetivo es crear un plan de desarrollo (estrat\u00e9gico y de implementaci\u00f3n) de corto, mediano y largo plazo para el fortalecimiento de las Artes, Humanidades y Ciencias Sociales en las unidades postulantes de las Universidades de Talca y O\u0092Higgins, incorporando inter-transdisciplina (I-TD) y sinergia interuniversitaria (S-IU), que permita transformar de manera innovadora procesos acad\u00e9micos de gesti\u00f3n y gobernanza,\r\nformaci\u00f3n de pre y postgrado, generaci\u00f3n y transferencia de nuevo conocimiento, creaci\u00f3n y tecnolog\u00eda, v\u00ednculo territorial bidireccional con el medio que las cobija y, promover transversalmente la equidad de g\u00e9nero y el liderazgo femenino, los derechos humanos, el patrimonio cultural, la salud mental y el bienestar psicol\u00f3gico,\r\npara as\u00ed aportar conjuntamente a las necesidades regionales y al logro de una mejor calidad de vida de los actuales y futuros habitantes de sus comunidades.\r\n\r\nTanto la Universidad de Talca como la Universidad de O\u0092Higgins tiene capacidades instaladas en estas \u00e1reas con distintos niveles desarrollo. En el caso de la  Universidad de Talca, las unidades acad\u00e9micas pertinentes a este concurso son las Facultades de: Psicolog\u00eda, Ciencias Jur\u00eddicas y Ciencias Sociales, Arquitectura, M\u00fasica y Dise\u00f1o; y el Instituto de Humanidades Abate Molina. En el caso de la Universidad de O\u0092Higgins las unidades acad\u00e9micas relevantes son el Instituto de Ciencias Sociales, la Escuela de Ciencias Sociales y el Instituto de Altos Estudios\r\nAudiovisuales.\r\n\r\nPara el desarrollo del proyecto, adem\u00e1s del trabajo de los directores, se realizar\u00e1 la contrataci\u00f3n de profesionales para tareas de gesti\u00f3n y planificaci\u00f3n del proyecto. Las autoridades de ambas universidades (rectores, vicerrectores, decanos\/as, entre otros) interactuar\u00e1n con el equipo mediante un consejo estrat\u00e9gico. Adem\u00e1s,\r\nse conformar\u00e1 una mesa de coordinaci\u00f3n interinstitucional que se organizar\u00e1 por ejes, considerando un coordinador\/a por eje estrat\u00e9gico.\r\n\r\nLa elaboraci\u00f3n del diagn\u00f3stico se centra en procesos participativos liderados por equipos internos que propicien la apropiaci\u00f3n de los resultados y contempla 4 etapas. La primera etapa de autoevaluaci\u00f3n seg\u00fan eje estrat\u00e9gico se centra en el levantamiento, sistematizaci\u00f3n y an\u00e1lisis de la situaci\u00f3n interna de ambas universidades. La segunda etapa de aplicaci\u00f3n de instrumentos de recolecci\u00f3n de antecedentes, de car\u00e1cter mixto y en terreno, tiene como prop\u00f3sito indagar en las brechas, expectativas y necesidades de los actores internos y externos, con\r\nrelaci\u00f3n a la transferencia de conocimientos y tecnolog\u00edas, vinculaci\u00f3n universidad-territorio, liderazgo femenino, oferta formativa en artes, humanidades y ciencias sociales, gobernanza, ciencia y conocimientos abiertos de parte de ambas instituciones. Esta etapa se realizar\u00e1 mediante entrevistas abiertas a actores claves, talleres participativos con miembros de la comunidad y entrevistas semiestructuradas a autoridades universitarias, comunales, provinciales y regionales. En la tercera etapa, de traducci\u00f3n del diagn\u00f3stico, se realizar\u00e1 la sistematizaci\u00f3n y categorizaci\u00f3n de la informaci\u00f3n obtenida en las etapas anteriores, utilizando como metodolog\u00eda el an\u00e1lisis de texto y categorizaci\u00f3n conceptual, junto con una triangulaci\u00f3n de los datos cuantitativos y cualitativos recabados tanto internamente en cada universidad como en el medio regional del Maule y O\u0092Higgins, teniendo como resultado un informe diagn\u00f3stico a ser validado, el que incluir\u00e1 una matriz con informaci\u00f3n sistematizada por eje tem\u00e1tico y la l\u00ednea base de indicadores. La cuarta y \u00faltima etapa consiste en la validaci\u00f3n del diagn\u00f3stico, a trav\u00e9s de la presentaci\u00f3n de los resultados a una red compuesta por diversos actores: representantes de la comunidad participante, expertos nacionales e internacionales, integrantes de la\r\nmesa de coordinaci\u00f3n interinstitucional, autoridades gubernamentales y, finalmente, a instancias colegiadas y autoridades unipersonales de ambas instituciones.\r\nPosterior del diagn\u00f3stico, se realizar\u00e1 un proceso de experiencia comparada, con la idea de observar los desarrollos de los diferentes ejes en otras instituciones de educaci\u00f3n superior nacionales e internacionales. Toda esta informaci\u00f3n permitir\u00e1 avanzar a la etapa de identificaci\u00f3n de brechas para identificar, por una partes,\r\nnuestra l\u00ednea de base y por otra la distancia de nuestro desarrollo con la experiencia de otras instituciones, considerando los contextos. Finalmente, estos insumos permitir\u00e1n, que de manera participativa con la comunidad universitaria y representantes de la comunidad regional, se elabore una propuesta de plan\r\nestrat\u00e9gico, que ser\u00e1 validado con actores internos y externos; y que se convertir\u00e1 en la hoja de ruta para los\r\npr\u00f3ximos a\u00f1os.\r\n\r\nEl presente proyecto se relaciona sin\u00e9rgicamente con los proyectos en desarrollo de Ingenier\u00eda 2030 y Ciencia 2030, que se encuentran en ejecuci\u00f3n en la Universidad de Talca. Estos proyectos buscan transformar las facultades de ciencias hacia una mayor vinculaci\u00f3n con el entorno mediante la I+D+i+ebct y transformar los\r\nplanes de formaci\u00f3n para las ingenier\u00edas, siendo coherente con el objetivo propuesto para la presente convocatoria. Por otra parte, la Universidad de Talca y la Universidad de O'Higgins cuentan con diversos organismos internos que pueden potenciar el trabajo del proyecto como la Direcci\u00f3n de Innovaci\u00f3n y transferencia, la Direcci\u00f3n de\r\nInvestigaci\u00f3n, Direcci\u00f3n General de Vinculaci\u00f3n con el Medio, Direcci\u00f3n General de Aseguramiento de la Calidad y Planificaci\u00f3n, Direcci\u00f3n de G\u00e9nero en el caso de la Universidad de Talca y la Direcci\u00f3n de Investigaci\u00f3n, Direcci\u00f3n de Vinculaci\u00f3n y Transferencia, Direcci\u00f3n de Postgrado, Direcci\u00f3n de Comunicaciones, Direcci\u00f3n de\r\nInternacionalizaci\u00f3n y Direcci\u00f3n de Equidad de G\u00e9nero y Diversidades en el caso de la Universidad de O'Higgins. Por \u00faltimo, la Universidad de Talca se encuentra desarrollando diferentes proyectos como Proyecto InES Redit,\r\nProyecto InES G\u00e9nero, Proyecto InEs I+D, Proyecto Ciencia Abierta, que buscan consolidar un modelo de gesti\u00f3n de la innovaci\u00f3n y emprendimiento basado en I+D interdisciplinario y transdisciplinario con perspectiva de g\u00e9nero, por una parte; as\u00ed como fortalecer y consolidar las capacidades institucionales actuales de soporte al\r\nproceso de innovaci\u00f3n basada en I+D por otra.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2023 - Diciembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26229\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Integraci\u00f3n de la tecnolog\u00eda de pizarra interactiva para la mejora de la experiencia y logro de aprendizajes de estudiantes en un Curso de Formaci\u00f3n General impartido en modalidad virtual de la Universidad de O\u0092Higgins: En la frontera \u00bfLo que las plantas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26229\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26229\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]TERCER CONCURSO DE PROYECTOS DE INNOVACI\u00d3N PEDAG\u00d3GICA (PIP) PARA ASIGNATURAS DE FORMACI\u00d3N GENERAL\/INTEGRAL.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26782\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Centro UOH de Biolog\u00eda de Sistemas para la Sanidad Vegetal (BioSaV-UOH)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26782\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26782\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Centro UOH de Biolog\u00eda de Sistemas para la Sanidad Vegetal (BioSaV-UOH)[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2023 - Julio 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26131\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Centro UOH de Bioingenier\u00eda (CUBI)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26131\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26131\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El c\u00e1ncer es una enfermedad gen\u00e9tica compleja y mortal que afecta a un gran n\u00famero de personas en Chile, con una alta tasa de mortalidad y un aumento constante en el n\u00famero de casos. Ante esta realidad, es crucial implementar la Medicina de Precisi\u00f3n en el pa\u00eds para brindar un tratamiento personalizado y mejorar los resultados para los pacientes. El Centro UOH de BioIngenier\u00eda (CUBI) se propone liderar este avance, enfoc\u00e1ndose en la regi\u00f3n de O'Higgins, Chile.\r\nEl CUBI busca crear mapas moleculares multi\u00f3micos de los c\u00e1nceres prevalentes en la regi\u00f3n, utilizando tecnolog\u00edas de vanguardia y algoritmos avanzados. Esto permitir\u00e1 comprender los perfiles gen\u00e9ticos y moleculares del c\u00e1ncer, as\u00ed como la heterogeneidad y evoluci\u00f3n som\u00e1tica de los tumores chilenos. El equipo propuesto por CUBI, con su destacada capacidad de secuenciaci\u00f3n gen\u00f3mica, procesamiento masivo de datos y experiencia en biolog\u00eda molecular y computacional, desempe\u00f1ar\u00e1 un papel protag\u00f3nico en el logro de estos objetivos.\r\nEl CUBI se organiza en tres l\u00edneas de investigaci\u00f3n principales. La primera l\u00ednea se centra en las tecnolog\u00edas gen\u00f3micas para el mapeo de genotipos, fenotipos y evoluci\u00f3n tumoral, dirigida por el Dr. Di Genova. Su objetivo es comprender los factores gen\u00e9ticos que contribuyen al c\u00e1ncer, as\u00ed como la variabilidad molecular y la evoluci\u00f3n som\u00e1tica de los tumores chilenos. La segunda l\u00ednea, liderada por el doctor Henao, se enfoca en las tecnolog\u00edas de imagen para el mapeo y evaluaci\u00f3n de fenotipos tumorales. Mediante el uso de im\u00e1genes histol\u00f3gicas y de ultrasonido, combinadas con la inteligencia artificial y modelos f\u00edsico\/matem\u00e1ticos, se busca identificar patrones morfol\u00f3gicos y topol\u00f3gicos asociados a biomarcadores o procesos mutacionales espec\u00edficos de los tumores. La tercera l\u00ednea de investigaci\u00f3n, liderada por el Dr. Krause, se centra en la utilizaci\u00f3n de modelos precl\u00ednicos para validar las relaciones fenotipo-genotipo desCUBIertas en las l\u00edneas de investigaci\u00f3n anteriores y la creaci\u00f3n de un biobanco regional. Esto permitir\u00e1 realizar estudios moleculares, cl\u00ednicos y epidemiol\u00f3gicos en la regi\u00f3n de O'Higgins, fortaleciendo la base de conocimientos y facilitando la aplicaci\u00f3n de los hallazgos en la pr\u00e1ctica cl\u00ednica.\r\nEl CUBI cuenta con un equipo interdisciplinario de investigadores j\u00f3venes, intermedios y senior, con l\u00edneas de investigaci\u00f3n claras y bien definidas. Adem\u00e1s, se ha establecido una s\u00f3lida red nacional e internacional de colaboraci\u00f3n con instituciones l\u00edderes en investigaci\u00f3n del c\u00e1ncer, como el IARC de Lyon, Francia, el ICR de Londres, UK y hospitales e instituciones en Chile.\r\nEl CUBI busca posicionarse como un centro pionero en la investigaci\u00f3n en medicina de precisi\u00f3n oncol\u00f3gica en Chile. Su objetivo principal es comprender y mapear la biolog\u00eda \u00fanica de los pacientes chilenos\/as con c\u00e1ncer, con el fin de brindar tratamientos m\u00e1s efectivos y mejorar las oportunidades para la regi\u00f3n. Con su infraestructura, equipo, red de colaboraci\u00f3n y enfoque multidisciplinario, el CUBI tiene el potencial de generar un impacto significativo en la sociedad chilena al avanzar en la comprensi\u00f3n del c\u00e1ncer y la implementaci\u00f3n de estrategias de tratamiento personalizado. Proyectamos que la operaci\u00f3n del CUBI tendr\u00e1 un impacto positivo en la regi\u00f3n y pa\u00eds en varios aspectos:\r\n1. Mejorar la atenci\u00f3n del c\u00e1ncer: El CUBI permitir\u00e1 una mejor comprensi\u00f3n de las caracter\u00edsticas gen\u00e9ticas y moleculares de los tumores en la poblaci\u00f3n regional y nacional. Esto conducir\u00e1 a un diagn\u00f3stico m\u00e1s preciso, una estratificaci\u00f3n m\u00e1s efectiva de los pacientes y una selecci\u00f3n m\u00e1s precisa de los tratamientos. Como resultado, los pacientes recibir\u00e1n terapias m\u00e1s efectivas, lo que mejorar\u00e1 sus resultados cl\u00ednicos y su calidad de vida. 2. Avances cient\u00edficos y tecnol\u00f3gicos: El centro promover\u00e1 el desarrollo y la aplicaci\u00f3n de tecnolog\u00edas de vanguardia y m\u00e9todos de an\u00e1lisis de datos avanzados. Esto fomentar\u00e1 la investigaci\u00f3n cient\u00edfica del c\u00e1ncer y permitir\u00e1 descubrir nuevas asociaciones gen\u00e9ticas y moleculares, as\u00ed como identificar posibles blancos terap\u00e9uticos. Estos avances no solo beneficiar\u00e1n a los pacientes de c\u00e1ncer en Chile, sino que tambi\u00e9n contribuir\u00e1n al conocimiento global en la lucha contra esta enfermedad. 3. Formaci\u00f3n y educaci\u00f3n: El centro brindar\u00e1 oportunidades de formaci\u00f3n y capacitaci\u00f3n para estudiantes, investigadores y profesionales de la salud interesados en la medicina de precisi\u00f3n en oncolog\u00eda. Esto fortalecer\u00e1 la capacidad cient\u00edfica y cl\u00ednica de la regi\u00f3n, permitiendo la formaci\u00f3n de especialistas altamente calificados en el diagn\u00f3stico y tratamiento del c\u00e1ncer. 4. Impacto socioecon\u00f3mico: La detecci\u00f3n temprana, el tratamiento personalizado y la reducci\u00f3n de los efectos secundarios innecesarios pueden mejorar la eficiencia de los sistemas de salud y disminuir los costos asociados con el c\u00e1ncer. Adem\u00e1s, la generaci\u00f3n de conocimiento cient\u00edfico y tecnol\u00f3gico puede impulsar la innovaci\u00f3n y el desarrollo de la industria biotecnol\u00f3gica en la regi\u00f3n, creando oportunidades econ\u00f3micas y empleo especializado.\r\nEn resumen, el CUBI tiene el potencial de generar un impacto significativo en la sociedad regional al mejorar la atenci\u00f3n m\u00e9dica, impulsar la investigaci\u00f3n cient\u00edfica, fortalecer la capacitaci\u00f3n y la colaboraci\u00f3n, y tener repercusiones socioecon\u00f3micas positivas. Al comprender y abordar la complejidad biol\u00f3gica del c\u00e1ncer en la poblaci\u00f3n chilena, se allana el camino para una atenci\u00f3n m\u00e1s efectiva y personalizada, y se brinda esperanza a los pacientes y sus familias en la lucha contra el c\u00e1ncer.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2023 - Noviembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26266\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fondo Desarrollo Interdisciplinario Universidad de O\u0092Higgins.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26266\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26266\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto UOH[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2023 - Julio 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26295\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Centro UOH de Bioingenier\u00eda (CUBI)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26295\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26295\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El c\u00e1ncer es una enfermedad gen\u00e9tica compleja y mortal que afecta a un gran n\u00famero de personas en Chile, con una alta tasa de mortalidad y un aumento constante en el n\u00famero de casos. Ante esta realidad, es crucial implementar la Medicina de Precisi\u00f3n en el pa\u00eds para brindar un tratamiento personalizado y mejorar los resultados para los pacientes. El Centro UOH de BioIngenier\u00eda (CUBI) se propone liderar este avance, enfoc\u00e1ndose en la regi\u00f3n de O'Higgins, Chile.\r\nEl CUBI busca crear mapas moleculares multi\u00f3micos de los c\u00e1nceres prevalentes en la regi\u00f3n, utilizando tecnolog\u00edas de vanguardia y algoritmos avanzados. Esto permitir\u00e1 comprender los perfiles gen\u00e9ticos y moleculares del c\u00e1ncer, as\u00ed como la heterogeneidad y evoluci\u00f3n som\u00e1tica de los tumores chilenos. El equipo propuesto por CUBI, con su destacada capacidad de secuenciaci\u00f3n gen\u00f3mica, procesamiento masivo de datos y experiencia en biolog\u00eda molecular y computacional, desempe\u00f1ar\u00e1 un papel protag\u00f3nico en el logro de estos objetivos.\r\nEl CUBI se organiza en tres l\u00edneas de investigaci\u00f3n principales. La primera l\u00ednea se centra en las tecnolog\u00edas gen\u00f3micas para el mapeo de genotipos, fenotipos y evoluci\u00f3n tumoral, dirigida por el Dr. Di Genova. Su objetivo es comprender los factores gen\u00e9ticos que contribuyen al c\u00e1ncer, as\u00ed como la variabilidad molecular y la evoluci\u00f3n som\u00e1tica de los tumores chilenos. La segunda l\u00ednea, liderada por el doctor Henao, se enfoca en las tecnolog\u00edas de imagen para el mapeo y evaluaci\u00f3n de fenotipos tumorales. Mediante el uso de im\u00e1genes histol\u00f3gicas y de ultrasonido, combinadas con la inteligencia artificial y modelos f\u00edsico\/matem\u00e1ticos, se busca identificar patrones morfol\u00f3gicos y topol\u00f3gicos asociados a biomarcadores o procesos mutacionales espec\u00edficos de los tumores. La tercera l\u00ednea de investigaci\u00f3n, liderada por el Dr. Krause, se centra en la utilizaci\u00f3n de modelos precl\u00ednicos para validar las relaciones fenotipo-genotipo desCUBIertas en las l\u00edneas de investigaci\u00f3n anteriores y la creaci\u00f3n de un biobanco regional. Esto permitir\u00e1 realizar estudios moleculares, cl\u00ednicos y epidemiol\u00f3gicos en la regi\u00f3n de O'Higgins, fortaleciendo la base de conocimientos y facilitando la aplicaci\u00f3n de los hallazgos en la pr\u00e1ctica cl\u00ednica.\r\nEl CUBI cuenta con un equipo interdisciplinario de investigadores j\u00f3venes, intermedios y senior, con l\u00edneas de investigaci\u00f3n claras y bien definidas. Adem\u00e1s, se ha establecido una s\u00f3lida red nacional e internacional de colaboraci\u00f3n con instituciones l\u00edderes en investigaci\u00f3n del c\u00e1ncer, como el IARC de Lyon, Francia, el ICR de Londres, UK y hospitales e instituciones en Chile.\r\nEl CUBI busca posicionarse como un centro pionero en la investigaci\u00f3n en medicina de precisi\u00f3n oncol\u00f3gica en Chile. Su objetivo principal es comprender y mapear la biolog\u00eda \u00fanica de los pacientes chilenos\/as con c\u00e1ncer, con el fin de brindar tratamientos m\u00e1s efectivos y mejorar las oportunidades para la regi\u00f3n. Con su infraestructura, equipo, red de colaboraci\u00f3n y enfoque multidisciplinario, el CUBI tiene el potencial de generar un impacto significativo en la sociedad chilena al avanzar en la comprensi\u00f3n del c\u00e1ncer y la implementaci\u00f3n de estrategias de tratamiento personalizado. Proyectamos que la operaci\u00f3n del CUBI tendr\u00e1 un impacto positivo en la regi\u00f3n y pa\u00eds en varios aspectos:\r\n1. Mejorar la atenci\u00f3n del c\u00e1ncer: El CUBI permitir\u00e1 una mejor comprensi\u00f3n de las caracter\u00edsticas gen\u00e9ticas y moleculares de los tumores en la poblaci\u00f3n regional y nacional. Esto conducir\u00e1 a un diagn\u00f3stico m\u00e1s preciso, una estratificaci\u00f3n m\u00e1s efectiva de los pacientes y una selecci\u00f3n m\u00e1s precisa de los tratamientos. Como resultado, los pacientes recibir\u00e1n terapias m\u00e1s efectivas, lo que mejorar\u00e1 sus resultados cl\u00ednicos y su calidad de vida. 2. Avances cient\u00edficos y tecnol\u00f3gicos: El centro promover\u00e1 el desarrollo y la aplicaci\u00f3n de tecnolog\u00edas de vanguardia y m\u00e9todos de an\u00e1lisis de datos avanzados. Esto fomentar\u00e1 la investigaci\u00f3n cient\u00edfica del c\u00e1ncer y permitir\u00e1 descubrir nuevas asociaciones gen\u00e9ticas y moleculares, as\u00ed como identificar posibles blancos terap\u00e9uticos. Estos avances no solo beneficiar\u00e1n a los pacientes de c\u00e1ncer en Chile, sino que tambi\u00e9n contribuir\u00e1n al conocimiento global en la lucha contra esta enfermedad. 3. Formaci\u00f3n y educaci\u00f3n: El centro brindar\u00e1 oportunidades de formaci\u00f3n y capacitaci\u00f3n para estudiantes, investigadores y profesionales de la salud interesados en la medicina de precisi\u00f3n en oncolog\u00eda. Esto fortalecer\u00e1 la capacidad cient\u00edfica y cl\u00ednica de la regi\u00f3n, permitiendo la formaci\u00f3n de especialistas altamente calificados en el diagn\u00f3stico y tratamiento del c\u00e1ncer. 4. Impacto socioecon\u00f3mico: La detecci\u00f3n temprana, el tratamiento personalizado y la reducci\u00f3n de los efectos secundarios innecesarios pueden mejorar la eficiencia de los sistemas de salud y disminuir los costos asociados con el c\u00e1ncer. Adem\u00e1s, la generaci\u00f3n de conocimiento cient\u00edfico y tecnol\u00f3gico puede impulsar la innovaci\u00f3n y el desarrollo de la industria biotecnol\u00f3gica en la regi\u00f3n, creando oportunidades econ\u00f3micas y empleo especializado.\r\nEn resumen, el CUBI tiene el potencial de generar un impacto significativo en la sociedad regional al mejorar la atenci\u00f3n m\u00e9dica, impulsar la investigaci\u00f3n cient\u00edfica, fortalecer la capacitaci\u00f3n y la colaboraci\u00f3n, y tener repercusiones socioecon\u00f3micas positivas. Al comprender y abordar la complejidad biol\u00f3gica del c\u00e1ncer en la poblaci\u00f3n chilena, se allana el camino para una atenci\u00f3n m\u00e1s efectiva y personalizada, y se brinda esperanza a los pacientes y sus familias en la lucha contra el c\u00e1ncer.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2023 - Noviembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26395\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fondo Desarrollo Interdisciplinario Universidad de O\u0092Higgins.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26395\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26395\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto UOH[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2023 - Julio 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26947\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Centro UOH de Bioingenier\u00eda (CUBI)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26947\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26947\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El c\u00e1ncer es una enfermedad gen\u00e9tica compleja y mortal que afecta a un gran n\u00famero de personas en Chile, con una alta tasa de mortalidad y un aumento constante en el n\u00famero de casos. Ante esta realidad, es crucial implementar la Medicina de Precisi\u00f3n en el pa\u00eds para brindar un tratamiento personalizado y mejorar los resultados para los pacientes. El Centro UOH de BioIngenier\u00eda (CUBI) se propone liderar este avance, enfoc\u00e1ndose en la regi\u00f3n de O'Higgins, Chile.\r\nEl CUBI busca crear mapas moleculares multi\u00f3micos de los c\u00e1nceres prevalentes en la regi\u00f3n, utilizando tecnolog\u00edas de vanguardia y algoritmos avanzados. Esto permitir\u00e1 comprender los perfiles gen\u00e9ticos y moleculares del c\u00e1ncer, as\u00ed como la heterogeneidad y evoluci\u00f3n som\u00e1tica de los tumores chilenos. El equipo propuesto por CUBI, con su destacada capacidad de secuenciaci\u00f3n gen\u00f3mica, procesamiento masivo de datos y experiencia en biolog\u00eda molecular y computacional, desempe\u00f1ar\u00e1 un papel protag\u00f3nico en el logro de estos objetivos.\r\nEl CUBI se organiza en tres l\u00edneas de investigaci\u00f3n principales. La primera l\u00ednea se centra en las tecnolog\u00edas gen\u00f3micas para el mapeo de genotipos, fenotipos y evoluci\u00f3n tumoral, dirigida por el Dr. Di Genova. Su objetivo es comprender los factores gen\u00e9ticos que contribuyen al c\u00e1ncer, as\u00ed como la variabilidad molecular y la evoluci\u00f3n som\u00e1tica de los tumores chilenos. La segunda l\u00ednea, liderada por el doctor Henao, se enfoca en las tecnolog\u00edas de imagen para el mapeo y evaluaci\u00f3n de fenotipos tumorales. Mediante el uso de im\u00e1genes histol\u00f3gicas y de ultrasonido, combinadas con la inteligencia artificial y modelos f\u00edsico\/matem\u00e1ticos, se busca identificar patrones morfol\u00f3gicos y topol\u00f3gicos asociados a biomarcadores o procesos mutacionales espec\u00edficos de los tumores. La tercera l\u00ednea de investigaci\u00f3n, liderada por el Dr. Krause, se centra en la utilizaci\u00f3n de modelos precl\u00ednicos para validar las relaciones fenotipo-genotipo desCUBIertas en las l\u00edneas de investigaci\u00f3n anteriores y la creaci\u00f3n de un biobanco regional. Esto permitir\u00e1 realizar estudios moleculares, cl\u00ednicos y epidemiol\u00f3gicos en la regi\u00f3n de O'Higgins, fortaleciendo la base de conocimientos y facilitando la aplicaci\u00f3n de los hallazgos en la pr\u00e1ctica cl\u00ednica.\r\nEl CUBI cuenta con un equipo interdisciplinario de investigadores j\u00f3venes, intermedios y senior, con l\u00edneas de investigaci\u00f3n claras y bien definidas. Adem\u00e1s, se ha establecido una s\u00f3lida red nacional e internacional de colaboraci\u00f3n con instituciones l\u00edderes en investigaci\u00f3n del c\u00e1ncer, como el IARC de Lyon, Francia, el ICR de Londres, UK y hospitales e instituciones en Chile.\r\nEl CUBI busca posicionarse como un centro pionero en la investigaci\u00f3n en medicina de precisi\u00f3n oncol\u00f3gica en Chile. Su objetivo principal es comprender y mapear la biolog\u00eda \u00fanica de los pacientes chilenos\/as con c\u00e1ncer, con el fin de brindar tratamientos m\u00e1s efectivos y mejorar las oportunidades para la regi\u00f3n. Con su infraestructura, equipo, red de colaboraci\u00f3n y enfoque multidisciplinario, el CUBI tiene el potencial de generar un impacto significativo en la sociedad chilena al avanzar en la comprensi\u00f3n del c\u00e1ncer y la implementaci\u00f3n de estrategias de tratamiento personalizado. Proyectamos que la operaci\u00f3n del CUBI tendr\u00e1 un impacto positivo en la regi\u00f3n y pa\u00eds en varios aspectos:\r\n1. Mejorar la atenci\u00f3n del c\u00e1ncer: El CUBI permitir\u00e1 una mejor comprensi\u00f3n de las caracter\u00edsticas gen\u00e9ticas y moleculares de los tumores en la poblaci\u00f3n regional y nacional. Esto conducir\u00e1 a un diagn\u00f3stico m\u00e1s preciso, una estratificaci\u00f3n m\u00e1s efectiva de los pacientes y una selecci\u00f3n m\u00e1s precisa de los tratamientos. Como resultado, los pacientes recibir\u00e1n terapias m\u00e1s efectivas, lo que mejorar\u00e1 sus resultados cl\u00ednicos y su calidad de vida. 2. Avances cient\u00edficos y tecnol\u00f3gicos: El centro promover\u00e1 el desarrollo y la aplicaci\u00f3n de tecnolog\u00edas de vanguardia y m\u00e9todos de an\u00e1lisis de datos avanzados. Esto fomentar\u00e1 la investigaci\u00f3n cient\u00edfica del c\u00e1ncer y permitir\u00e1 descubrir nuevas asociaciones gen\u00e9ticas y moleculares, as\u00ed como identificar posibles blancos terap\u00e9uticos. Estos avances no solo beneficiar\u00e1n a los pacientes de c\u00e1ncer en Chile, sino que tambi\u00e9n contribuir\u00e1n al conocimiento global en la lucha contra esta enfermedad. 3. Formaci\u00f3n y educaci\u00f3n: El centro brindar\u00e1 oportunidades de formaci\u00f3n y capacitaci\u00f3n para estudiantes, investigadores y profesionales de la salud interesados en la medicina de precisi\u00f3n en oncolog\u00eda. Esto fortalecer\u00e1 la capacidad cient\u00edfica y cl\u00ednica de la regi\u00f3n, permitiendo la formaci\u00f3n de especialistas altamente calificados en el diagn\u00f3stico y tratamiento del c\u00e1ncer. 4. Impacto socioecon\u00f3mico: La detecci\u00f3n temprana, el tratamiento personalizado y la reducci\u00f3n de los efectos secundarios innecesarios pueden mejorar la eficiencia de los sistemas de salud y disminuir los costos asociados con el c\u00e1ncer. Adem\u00e1s, la generaci\u00f3n de conocimiento cient\u00edfico y tecnol\u00f3gico puede impulsar la innovaci\u00f3n y el desarrollo de la industria biotecnol\u00f3gica en la regi\u00f3n, creando oportunidades econ\u00f3micas y empleo especializado.\r\nEn resumen, el CUBI tiene el potencial de generar un impacto significativo en la sociedad regional al mejorar la atenci\u00f3n m\u00e9dica, impulsar la investigaci\u00f3n cient\u00edfica, fortalecer la capacitaci\u00f3n y la colaboraci\u00f3n, y tener repercusiones socioecon\u00f3micas positivas. Al comprender y abordar la complejidad biol\u00f3gica del c\u00e1ncer en la poblaci\u00f3n chilena, se allana el camino para una atenci\u00f3n m\u00e1s efectiva y personalizada, y se brinda esperanza a los pacientes y sus familias en la lucha contra el c\u00e1ncer.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FONDEF ID23I10138<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2023 - Julio 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26473\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desarrollo de prototipo de convertidor modular para la reutilizaci\u00f3n de bater\u00edas descartadas de electromovilidad\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26473\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26473\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En los \u00faltimos a\u00f1os, la electromovilidad a nivel mundial ha tenido un aumento significativo, el que ha sido motivado por la necesidad mundial de disminuir la dependencia de combustibles f\u00f3siles, para ir hacia una matriz energ\u00e9tica basada en fuentes de energ\u00edas m\u00e1s limpias, menos contaminantes y amigables con el medio ambiente. En recientes a\u00f1os ha habido un aumento significativo de veh\u00edculos h\u00edbridos y totalmente el\u00e9ctricos transitando en las calles del mundo. Por ejemplo, el a\u00f1o 2021 hubieron cerca de 16.5 millones de este tipo de veh\u00edculos y se espera un aumento exponencial en los a\u00f1os siguientes. Chile no est\u00e1 ajeno a esta tendencia, teni\u00e9ndose que la venta de modelos el\u00e9ctricos en 2011 hasta agosto de 2022 ha sido de 1.522 veh\u00edculos 100% el\u00e9ctricos (EV), a los que se suman 607 modelos h\u00edbridos Plug-In (PHEV), conformando un parque total de 2.129. Adem\u00e1s, se espera que al 2030 el parque de veh\u00edculos el\u00e9ctricos alcance las 80.000 unidades circulando. \r\n\r\nAl analizar un veh\u00edculo el\u00e9ctrico, se tiene que, de manera general, sus componentes son bastantes similares a los presentes en veh\u00edculos de combusti\u00f3n interna. La diferencia principal radica en que los veh\u00edculos totalmente el\u00e9ctricos o h\u00edbridos tienen incorporado un banco de bater\u00edas, el que se compone de cientos de celdas de bater\u00edas de ion litio interconectadas entre s\u00ed. En este sentido, la energ\u00eda almacenada por un banco de bater\u00edas se caracteriza por su capacidad nominal. Notar que la capacidad de una bater\u00eda va disminuyendo con su uso, por lo cual, es un indicador del nivel de degradaci\u00f3n de la misma. Una pr\u00e1ctica com\u00fan en electromovilidad es reemplazar el banco de bater\u00edas cuando \u00e9ste ha alcanzado ha alcanzado un 80% de su capacidad nominal. Notar que, en este contexto, si bien el banco de bater\u00edas descartado no puede ser utilizado en aplicaciones de electromovilidad, si puede ser utilizado en otras aplicaciones menos demandantes como almacenamiento est\u00e1tico de energ\u00eda.\r\n\r\nTomando en cuenta el auge de la electromovilidad en el mundo y que un banco de bater\u00edas de un veh\u00edculo el\u00e9ctrico t\u00edpicamente tiene una vida \u00fatil de 10 a\u00f1os, se tendr\u00e1 en el corto plazo, a nivel mundial, un gran n\u00famero de bancos de bater\u00edas desechados de aplicaciones de electromovilidad. En este escenario, en este proyecto, se detecta el problema de qu\u00e9 hacer con la gran cantidad de bater\u00edas desechadas que habr\u00e1 a nivel mundial en pocos a\u00f1os.  Notar que este tipo de bater\u00edas no pueden ser desechadas en vertederos de basura ya que contienen materiales peligrosos tanto para los seres humanos como para el medio ambiente. Adem\u00e1s, no pueden ser almacenadas en los domicilios particulares de los due\u00f1os de los veh\u00edculos, ya que, si son manipulados incorrectamente, pueden explotar, generando fuego y gases nocivos. En base a esto, la oportunidad que se aborda con este proyecto es de valorizar este residuo (bater\u00edas desechadas) en un producto de valor para el mercado y la sociedad y que pueda ser utilizado como almacenamiento de energ\u00eda en otras aplicaciones. En particular, proponemos una topolog\u00eda de electr\u00f3nica de potencia capaz de integrar bater\u00edas de distintos tipos (voltaje nominal, capacidad, qu\u00edmica, etc.) y mediante t\u00e9cnicas de control avanzadas, hacer funcionar el dispositivo como una sola entidad desde el punto de vista de la aplicaci\u00f3n y\/o usuario final y al mismo tiempo, gestionar internamente los estados (estado de carga, nivel de degradaci\u00f3n, etc.) de todas las bater\u00edas integradas por la topolog\u00eda (para optimizar el funcionamiento y autonom\u00eda del dispositivo).[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FONDEF ID23I10138<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2023 - Julio 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26593\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desarrollo de prototipo de convertidor modular para la reutilizaci\u00f3n de bater\u00edas descartadas de electromovilidad\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26593\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26593\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En los \u00faltimos a\u00f1os, la electromovilidad a nivel mundial ha tenido un aumento significativo, el que ha sido motivado por la necesidad mundial de disminuir la dependencia de combustibles f\u00f3siles, para ir hacia una matriz energ\u00e9tica basada en fuentes de energ\u00edas m\u00e1s limpias, menos contaminantes y amigables con el medio ambiente. En recientes a\u00f1os ha habido un aumento significativo de veh\u00edculos h\u00edbridos y totalmente el\u00e9ctricos transitando en las calles del mundo. Por ejemplo, el a\u00f1o 2021 hubieron cerca de 16.5 millones de este tipo de veh\u00edculos y se espera un aumento exponencial en los a\u00f1os siguientes. Chile no est\u00e1 ajeno a esta tendencia, teni\u00e9ndose que la venta de modelos el\u00e9ctricos en 2011 hasta agosto de 2022 ha sido de 1.522 veh\u00edculos 100% el\u00e9ctricos (EV), a los que se suman 607 modelos h\u00edbridos Plug-In (PHEV), conformando un parque total de 2.129. Adem\u00e1s, se espera que al 2030 el parque de veh\u00edculos el\u00e9ctricos alcance las 80.000 unidades circulando. \r\n\r\nAl analizar un veh\u00edculo el\u00e9ctrico, se tiene que, de manera general, sus componentes son bastantes similares a los presentes en veh\u00edculos de combusti\u00f3n interna. La diferencia principal radica en que los veh\u00edculos totalmente el\u00e9ctricos o h\u00edbridos tienen incorporado un banco de bater\u00edas, el que se compone de cientos de celdas de bater\u00edas de ion litio interconectadas entre s\u00ed. En este sentido, la energ\u00eda almacenada por un banco de bater\u00edas se caracteriza por su capacidad nominal. Notar que la capacidad de una bater\u00eda va disminuyendo con su uso, por lo cual, es un indicador del nivel de degradaci\u00f3n de la misma. Una pr\u00e1ctica com\u00fan en electromovilidad es reemplazar el banco de bater\u00edas cuando \u00e9ste ha alcanzado ha alcanzado un 80% de su capacidad nominal. Notar que, en este contexto, si bien el banco de bater\u00edas descartado no puede ser utilizado en aplicaciones de electromovilidad, si puede ser utilizado en otras aplicaciones menos demandantes como almacenamiento est\u00e1tico de energ\u00eda.\r\n\r\nTomando en cuenta el auge de la electromovilidad en el mundo y que un banco de bater\u00edas de un veh\u00edculo el\u00e9ctrico t\u00edpicamente tiene una vida \u00fatil de 10 a\u00f1os, se tendr\u00e1 en el corto plazo, a nivel mundial, un gran n\u00famero de bancos de bater\u00edas desechados de aplicaciones de electromovilidad. En este escenario, en este proyecto, se detecta el problema de qu\u00e9 hacer con la gran cantidad de bater\u00edas desechadas que habr\u00e1 a nivel mundial en pocos a\u00f1os.  Notar que este tipo de bater\u00edas no pueden ser desechadas en vertederos de basura ya que contienen materiales peligrosos tanto para los seres humanos como para el medio ambiente. Adem\u00e1s, no pueden ser almacenadas en los domicilios particulares de los due\u00f1os de los veh\u00edculos, ya que, si son manipulados incorrectamente, pueden explotar, generando fuego y gases nocivos. En base a esto, la oportunidad que se aborda con este proyecto es de valorizar este residuo (bater\u00edas desechadas) en un producto de valor para el mercado y la sociedad y que pueda ser utilizado como almacenamiento de energ\u00eda en otras aplicaciones. En particular, proponemos una topolog\u00eda de electr\u00f3nica de potencia capaz de integrar bater\u00edas de distintos tipos (voltaje nominal, capacidad, qu\u00edmica, etc.) y mediante t\u00e9cnicas de control avanzadas, hacer funcionar el dispositivo como una sola entidad desde el punto de vista de la aplicaci\u00f3n y\/o usuario final y al mismo tiempo, gestionar internamente los estados (estado de carga, nivel de degradaci\u00f3n, etc.) de todas las bater\u00edas integradas por la topolog\u00eda (para optimizar el funcionamiento y autonom\u00eda del dispositivo).[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2023 - Diciembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de Chile - Proyecto FONDEF ID21I10067<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26583\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Oportunidades y desaf\u00edos de la co-docencia en la formaci\u00f3n inicial de docentes de matem\u00e1ticas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26583\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26583\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]A lo largo de los \u00faltimos dos semestres universitarios (2\u00ba-2022, 1\u00ba-2023), Valentina y yo hemos trabajado en co-docencia en el desarrollo de dos asignaturas con foco en  el contenido de probabilidades y estad\u00edstica. En ambas oportunidades, nos hemos enfrentado a diferentes desaf\u00edos relativos a ense\u00f1ar a ense\u00f1ar este contenido, junto con tensiones curriculares-pr\u00e1cticas-te\u00f3ricas que hemos identificado cuando impartimos clases. En ambas oportunidades adoptamos distintos enfoques: en la primera instancia,, cada una se responsabiliz\u00f3 por una unidad de la asignatura; en cambio,  en la segunda instancia, cada una aport\u00f3 desde su expertise al dise\u00f1o e implementaci\u00f3n de la asignatura. Para el segundo semestre del presente a\u00f1o, trabajaremos nuevamente en co-docencia, pero esta vez desde un nuevo enfoque en el cual  cada una ser\u00e1 la docente a cargo de una secci\u00f3n de estudiantes. Este desaf\u00edo nos lleva nuevamente a reflexionar sobre este proceso, con especial \u00e9nfasis en conocer la percepci\u00f3n del futuro profesorado sobre este proceso de ense\u00f1anza conjunta, ya que es un aspecto que no hemos consideramos en las implementaciones previas. Esperamos identificar qu\u00e9 oportunidades de aprendizaje profesional genera este trabajo colaborativo y c\u00f3mo percibe el futuro profesorado esta modalidad de trabajo docente. As\u00ed, luego de un an\u00e1lisis de contenido de transcripciones de reuniones, focus group del estudiantado y de ticket de salida en tres hitos del semestre, esperamos generar pautas y directrices sustentadas en evidencia para la co-docencia en la formaci\u00f3n inicial de docentes de matem\u00e1tica, que permitan orientar esta pr\u00e1ctica colaborativa en otros espacios universitarios.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2023 - Diciembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Ciencia, Tecnolog\u00eda, Conocimiento e Innovaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26096\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Festival de la Ciencia 2023\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26096\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26096\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Festival de la Ciencia 2023[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2023 - Diciembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Ciencia, Tecnolog\u00eda, Conocimiento e Innovaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26851\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Festival de la Ciencia 2023\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26851\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26851\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Festival de la Ciencia 2023[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2023 - Diciembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Municipalidad de San Vicente de Tagua Tagua<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26149\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Tagua Tagua Milenaria\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26149\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26149\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Estudio Paleoadn en los yacimientos de Taguatagua[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> URO2395<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26879\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortalecimiento de la red de apoyo para las personas en situaci\u00f3n de discapacidad de la regi\u00f3n de O&#8217;Higgins.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26879\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26879\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Fortalecer la red comunitaria de apoyo para las personas en situaci\u00f3n de discapacidad en la regi\u00f3n de O'Higgins a trav\u00e9s de la generaci\u00f3n de conocimiento, el perfeccionamiento profesional y aplicaci\u00f3n de metodolog\u00eda A+S en CCR y otros organismos pertinentes de la regi\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> AMSUD220013<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2023 - Junio 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26476\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Networked control of hybrid systems by semidefinite programming with applications in industry 4.0\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26476\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26476\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto internacional de colaboraci\u00f3n que se enfoca en el an\u00e1lisis de estabilidad y dise\u00f1o de sistemas de control y estimaci\u00f3n para sistemas h\u00edbridos que operan en redes de industria 4.0. El objetivo es desarrollar m\u00e9todos y algritmos que puedan lidiar con desaf\u00edos como detecci\u00f3n de fallas, monitoreo, efectos de muestreo, cuantizaci\u00f3n, limitaciones de ancho de banda y magnitud de se\u00f1ales, presencia de incertezas, retardos, no linealidades y p\u00e9rdidas de paquetes. Para obtener soluciones no conservativas, se considera el uso de herramientas de programaci\u00f3n semidefinida.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ID 688-7-LE23<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2023 - Septiembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26429\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estudio de costos de producci\u00f3n de miel material\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26429\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26429\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Los objetivos de este estudio, los cuales fueron desarrollados en un periodo de tres meses estipulados por ODEPA, incluyen la elaboraci\u00f3n de itinerarios t\u00e9cnicos y fichas de costos que reflejen la diversidad geogr\u00e1fica y tecnol\u00f3gica del sector ap\u00edcola chileno. Adem\u00e1s, considera una propuesta metodol\u00f3gica para la recolecci\u00f3n de informaci\u00f3n y un modelo de ficha de costo que permita su actualizaci\u00f3n continua.\r\n\r\nPara el logro de estos objetivos, este estudio incorpor\u00f3, las siguientes actividades y consideraciones metodol\u00f3gicas: \r\n-\tSe realiz\u00f3 una revisi\u00f3n bibliogr\u00e1fica relevante y relacionada con el objeto del estudio, se llevaron a cabo reuniones, entrevistas y actividades participativas con actores claves para desarrollar y\/o validar los productos solicitados, los cuales fueron desarrolladas de manera remota o presencial seg\u00fan la macrozona respectiva. \r\n-\tEn la construcci\u00f3n de las fichas de costos, se incorporaron unidades de medida, precios de mercado recopilados y fuentes de informaci\u00f3n. Tambi\u00e9n se incluy\u00f3 un componente financiero que abord\u00f3 el costo de financiar las labores e insumos mediante un cr\u00e9dito con una duraci\u00f3n promedio y una tasa de inter\u00e9s de mercado. Adem\u00e1s, se realiz\u00f3 un an\u00e1lisis de sensibilidad que contempl\u00f3 diferentes rendimientos.\r\n-\tSe consider\u00f3 la demanda de los cultivos m\u00e1s representativos en la escala geogr\u00e1fica que requieren la prestaci\u00f3n de servicios de polinizaci\u00f3n, determinando la cantidad promedio de servicios de polinizaci\u00f3n que un apicultor realiza con sus colmenas. \r\n-\tSe proporcion\u00f3 una descripci\u00f3n detallada de la metodolog\u00eda de recolecci\u00f3n de datos, incluyendo un contenido procedimental que permite su actualizaci\u00f3n continua.\r\n\r\nEspec\u00edficamente en este estudio se detallan los siguientes productos desarrollados:\r\n&#61607;\tItinerarios t\u00e9cnicos para la producci\u00f3n de miel, la reproducci\u00f3n de material biol\u00f3gico ap\u00edcola y la prestaci\u00f3n de servicios de polinizaci\u00f3n.\r\n&#61607;\tFichas de costos espec\u00edficas para la producci\u00f3n de miel, la reproducci\u00f3n de material biol\u00f3gico ap\u00edcola y la prestaci\u00f3n de servicios de polinizaci\u00f3n en la escala geogr\u00e1fica propuesta por el oferente adjudicado.\r\n&#61607;\tPropuesta de metodolog\u00eda para la recolecci\u00f3n de informaci\u00f3n y un modelo est\u00e1ndar de ficha de costo.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2023 - Mayo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26263\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia Laboratorio Ecosistemas de Humedales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26263\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26263\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Dise\u00f1ar e implementar un >Laboratorio de Ecosistema de Humedales para el desarrollo y transferencia de herramientas biotecnol\u00f3gicas sustentables para la Reg\u00edon e O'Higgins, mediante monitoreo, extensi\u00f3n y educaci\u00f3n[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26289\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia Modelo de gesti\u00f3n para sistemas sanitarios rurales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26289\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26289\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]I+D+i para la gesti\u00f3n y manejo de los recursos h\u00eddricos, mejora de la calidad del agua, optimizaci\u00f3n y reutilizaci\u00f3n del agua\r\nde riego y su tecnificaci\u00f3n[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2023 - Mayo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26310\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia Laboratorio Ecosistemas de Humedales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26310\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26310\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Dise\u00f1ar e implementar un >Laboratorio de Ecosistema de Humedales para el desarrollo y transferencia de herramientas biotecnol\u00f3gicas sustentables para la Reg\u00edon e O'Higgins, mediante monitoreo, extensi\u00f3n y educaci\u00f3n[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2023 - Mayo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26375\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia Laboratorio Ecosistemas de Humedales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26375\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26375\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Dise\u00f1ar e implementar un >Laboratorio de Ecosistema de Humedales para el desarrollo y transferencia de herramientas biotecnol\u00f3gicas sustentables para la Reg\u00edon e O'Higgins, mediante monitoreo, extensi\u00f3n y educaci\u00f3n[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2023 - Mayo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26392\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia Laboratorio Ecosistemas de Humedales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26392\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26392\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Dise\u00f1ar e implementar un >Laboratorio de Ecosistema de Humedales para el desarrollo y transferencia de herramientas biotecnol\u00f3gicas sustentables para la Reg\u00edon e O'Higgins, mediante monitoreo, extensi\u00f3n y educaci\u00f3n[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FIC IDI40048418-0<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2023 - Junio 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26594\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Energ\u00edas renovables para producci\u00f3n de Sal de C\u00e1huil\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26594\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26594\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Implementaci\u00f3n de una microrred de energ\u00edas renovables (solar, e\u00f3lica y geot\u00e9rmica) en el distrito salinero artesanal Barranca-La Villa de C\u00e1huil. Implementaci\u00f3n de una planta piloto geot\u00e9rmica de producci\u00f3n de sal y electrificaci\u00f3n de bombas y planta de yodaci\u00f3n comunitaria mediante energ\u00edas renovables no convencionales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FIC IDI40048418-0<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2023 - Junio 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26617\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Energ\u00edas renovables para producci\u00f3n de Sal de C\u00e1huil\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26617\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26617\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Implementaci\u00f3n de una microrred de energ\u00edas renovables (solar, e\u00f3lica y geot\u00e9rmica) en el distrito salinero artesanal Barranca-La Villa de C\u00e1huil. Implementaci\u00f3n de una planta piloto geot\u00e9rmica de producci\u00f3n de sal y electrificaci\u00f3n de bombas y planta de yodaci\u00f3n comunitaria mediante energ\u00edas renovables no convencionales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FIC IDI40048418-0<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2023 - Junio 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26849\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Energ\u00edas renovables para producci\u00f3n de Sal de C\u00e1huil\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26849\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26849\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Implementaci\u00f3n de una microrred de energ\u00edas renovables (solar, e\u00f3lica y geot\u00e9rmica) en el distrito salinero artesanal Barranca-La Villa de C\u00e1huil. Implementaci\u00f3n de una planta piloto geot\u00e9rmica de producci\u00f3n de sal y electrificaci\u00f3n de bombas y planta de yodaci\u00f3n comunitaria mediante energ\u00edas renovables no convencionales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2023 - Mayo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26898\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia Laboratorio Ecosistemas de Humedales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26898\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26898\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Dise\u00f1ar e implementar un >Laboratorio de Ecosistema de Humedales para el desarrollo y transferencia de herramientas biotecnol\u00f3gicas sustentables para la Reg\u00edon e O'Higgins, mediante monitoreo, extensi\u00f3n y educaci\u00f3n[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26899\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia Modelo de gesti\u00f3n para sistemas sanitarios rurales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26899\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26899\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]I+D+i para la gesti\u00f3n y manejo de los recursos h\u00eddricos, mejora de la calidad del agua, optimizaci\u00f3n y reutilizaci\u00f3n del agua\r\nde riego y su tecnificaci\u00f3n[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FIC IDI40048418-0<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2023 - Junio 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27043\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Energ\u00edas renovables para producci\u00f3n de Sal de C\u00e1huil\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27043\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27043\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Implementaci\u00f3n de una microrred de energ\u00edas renovables (solar, e\u00f3lica y geot\u00e9rmica) en el distrito salinero artesanal Barranca-La Villa de C\u00e1huil. Implementaci\u00f3n de una planta piloto geot\u00e9rmica de producci\u00f3n de sal y electrificaci\u00f3n de bombas y planta de yodaci\u00f3n comunitaria mediante energ\u00edas renovables no convencionales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ID23I10201<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2023 - Mayo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26393\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Uso de Nitroprusiato de Sodio (SNP) como generador de \u00f3xido n\u00edtrico para la preservaci\u00f3n de lacalidad de la cereza exportada a mercados distantes\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26393\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26393\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las p\u00e9rdidas de calidad de la fruta durante la post cosecha, es un problema global para la industria de la cereza. Estas son principalmente: perdida de firmeza, da\u00f1os mec\u00e1nicos, des\u00f3rdenes fisiol\u00f3gicos, pudriciones por hongos y una mala apariencia del pedicelo. Est\u00e1s p\u00e9rdidas pueden ir de 15 a 30%. La deshidrataci\u00f3n y el pardeamiento de la fruta durante el tr\u00e1nsito y comercializaci\u00f3n afecta la apariencia, sobre todo la del pedicelo lo que disminuye la aceptaci\u00f3n del consumidor. Adicionalmente, la p\u00e9rdida de agua acelera la degradaci\u00f3n de la clorofila perdiendo el pedicelo su color verde caracter\u00edstico. Prolongar el periodo donde la fruta se encuentra en una calidad comercializable luego del tr\u00e1nsito a destino es muy importante para pa\u00edses que, como Chile, necesitan de largos per\u00edodos de tr\u00e1nsito para llegar a sus mercados. Estos per\u00edodos se han alargado por problemas log\u00edsticos de transporte como los asociados al COVID-19, en 2022, que en el caso Chileno pasaron de 35 a 50 d\u00edas, causando p\u00e9rdidas por m\u00e1s de USD 1.000 millones.\r\nActualmente, la industria exportadora de la cereza utiliza una metodolog\u00eda est\u00e1ndar basada en la sanitizaci\u00f3n y aplicaci\u00f3n de fungicida en la l\u00ednea de procesamiento y en el control de la cadena de fr\u00edo y humedad y de la raz\u00f3n CO2\/O2 durante su transporte. Pese a toda la tecnolog\u00eda existente, a\u00fan se pierde 20 a 30% de fruta de alta calidad, estimado en unos USD 850 millones por temporada. Esta cifra aumenta al existir problemas log\u00edsticos en los puertos y aduanas de destino, arriesgando la rentabilidad anual de esta industria. Dar a la cereza una mejor vida en poscosecha, es un desaf\u00edo mayor que requiere nuevas tecnolog\u00edas de bajo costo. Basado en nuestra experiencia con inductores de NO para: la reducci\u00f3n de abscisi\u00f3n de frutos, el rompimiento de dormancia (1); la inducci\u00f3n de clorofila (2) y en resultados no publicados sobre el efecto del NO en la calidad de la cereza, se propone una formulaci\u00f3n y un m\u00e9todo de aplicaci\u00f3n de inductores de NO en etapas claves del proceso y transporte de la cereza. En ensayos preliminares hemos observadoque tratamientos con el generador de NO, Sodio Nitroprusiato, se alcanza a aumentar el tiempo de la cereza de calidad hasta 40 d\u00edas. Por lo que en esta propuesta nuestra hip\u00f3tesis es que: La aplicaci\u00f3n de \u00d3xido N\u00edtrico en la l\u00ednea de procesamiento y\/o transporte de la cereza de exportaci\u00f3n a trav\u00e9s de una formulaci\u00f3n a base a Nitroprusiato de Sodio mejora su postcosecha prolongando el periodo de calidad comercializable de la fruta. Esperamos que cuando esta tecnolog\u00eda alcance un nivel de TRL9 tendr\u00e1 como funci\u00f3n cr\u00edtica asegurar la calidad de las cerezas en periodos de transporte superiores a 40 d\u00edas. En la 1\u00b0 etapa se llegar\u00e1 a TRL6, optimizando dosis y formas de aplicaci\u00f3n y comprobando resultados en destino. Esto se har\u00e1 en especial durante el vaciado y desinfecci\u00f3n de frutos en agua para que el NO difunda en la pulpa, active sus antioxidantes y permita la mantenci\u00f3n del pedicelo verde, la reducci\u00f3n de pudriciones y otros par\u00e1metros como el pardeamiento en variedades bicolores.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ID23I10273<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2023 - Mayo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26228\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Detecci\u00f3n en campo y control biol\u00f3gico de Xanthomonas arboricola pv corylina en avellano europeo (Corylus avellana l) en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26228\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26228\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Actualmente el control de Xac se basa en el manejo agron\u00f3mico m\u00e1s el uso de cobre. Sin embargo, al igual que lo observado en otras bacterias como Pseudomonas syringae pv. syringae (en cerezo y otros vegetales) y X. a. pv. juglandis (en nogal), la p\u00e9rdida de susceptibilidad a productos c\u00fapricos es muy frecuente, obligando a aumentar dosis, con da\u00f1o al ecosistema y exacerbando la selecci\u00f3n de aislados bacterianos resistentes a este metal. Cabe destacar que ya se ha descrito cepas nacionales de Xac resistentes a cobre. Por lo tanto, para la producci\u00f3n del avellano es necesario fortalecer el Manejo Integrado Fitosanitario, que se basa en la eficiencia del diagn\u00f3stico, y en el desarrollo de nuevas herramientas de control. El proyecto implementar\u00e1 una estrategia de detecci\u00f3n de la bacteria a trav\u00e9s de LAMP en campo. Esta t\u00e9cnica es r\u00e1pida, espec\u00edfica, sensible y se puede realizar en el huerto. Sumado, a la detecci\u00f3n de genes asociados a resistencia a cobre. Adicionalmente, se implementar\u00e1 el uso de bacteri\u00f3fagos como control biol\u00f3gico complementario al manejo tradicional. A trav\u00e9s de la detecci\u00f3n temprana con LAMP y el uso de bacteri\u00f3fagos, se quiere promover una estrategia de control preventivo para evitar los problemas ya observados en otros cultivos como el nogal y el cerezo, donde la resistencia al cobre de las bacterias se ha transformado en un problema creciente, y con escasas soluciones viables que se sostengan en el tiempo. Los resultados que se obtendr\u00e1n gracias al desarrollo de este proyecto, favorecer\u00e1n una mayor calidad fitosanitaria del avellano en el pa\u00eds y una m\u00e1s alta y sostenida rentabilidad del cultivo a beneficio de viveristas y productores. \r\nFormulamos dos hip\u00f3tesis: \r\n1. La t\u00e9cnica LAMP permite la identificaci\u00f3n espec\u00edfica de Xac y de cepas potencialmente resistentes a cobre, directamente en material vegetal en campo.\r\n2. El uso de mezclas de bacteri\u00f3fagos permite el control preventivo del tiz\u00f3n bacteriano del avellano europeo causado por Xac.\r\n\r\nEl objetivo general de la propuesta es el paragua que permitir\u00e1 validar o menos las hip\u00f3tesis:\r\n\r\nDesarrollar la t\u00e9cnica LAMP para la detecci\u00f3n en campo de Xac en avellano europeo y una estrategia de control\r\nbiol\u00f3gico del Tiz\u00f3n Bacteriano por medio de una mezcla de bacteri\u00f3fagos.\r\n\r\nActualmente, no se cuenta con la t\u00e9cnica LAMP para la detecci\u00f3n de Xac y menos para pesquisar resistencia a\r\ncobre de los aislados. Tampoco un desarrollo de estrategias de control de Xac basada en bacteri\u00f3fagos, por lo que las\r\nperspectivas cient\u00edficas y econ\u00f3micas de esta propuesta son relevantes.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2023 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Ciencia, Tecnolog\u00eda, Conocimiento e Innovaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26095\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Proyecto PAR Explora O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26095\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26095\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]promover\u00e1n la socializaci\u00f3n del conocimiento y la instalaci\u00f3n de capacidades en comunidades educativas, con el prop\u00f3sito de fortalecer las competencias CTCI en ni\u00f1as, ni\u00f1os y adolescentes.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2023 - Noviembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>EXCITE Network<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27025\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27025\" aria-expanded=\"false\" aria-controls=\"collapse-27025\">\n                                            RHY2: Researching hybrid rhyolitic eruptions\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27025\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27025\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]This project aims to determine the intensive magmatic conditions and eruption triggering during the Mondaca-forming eruption (Southern Andes), likely occurred in ~1760 CE. We will apply geothermometers, geobarometers, and Rhyolite-MELTS. These results would provide new insight into the generation of hybrid rhyolitic eruptions.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FIC IDI 40048442-0<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2023 - Mayo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26021\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia de innovaci\u00f3n social: inclusi\u00f3n y turismo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26021\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26021\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Consolidar y fortalecer una nueva red de nodos de innovaci\u00f3n social que promueva la inclusi\u00f3n socio laboral en personas con alguna discapacidad, personas mayores, mujeres y personas en situaci\u00f3n de vulnerabilidad enfocada en los sectores econ\u00f3micos priorizados en la Estrategia de Desarrollo Regional 2011-2020 (EDRE) y de innovaci\u00f3n, priorizando el sector tur\u00edstico, y agroalimentario y la puesta en valor de la identidad cultural.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FIC IDI 40048442-0<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2023 - Mayo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26414\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia de innovaci\u00f3n social: inclusi\u00f3n y turismo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26414\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26414\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Consolidar y fortalecer una nueva red de nodos de innovaci\u00f3n social que promueva la inclusi\u00f3n socio laboral en personas con alguna discapacidad, personas mayores, mujeres y personas en situaci\u00f3n de vulnerabilidad enfocada en los sectores econ\u00f3micos priorizados en la Estrategia de Desarrollo Regional 2011-2020 (EDRE) y de innovaci\u00f3n, priorizando el sector tur\u00edstico, y agroalimentario y la puesta en valor de la identidad cultural.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FIC IDI 40048442-0<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2023 - Mayo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26441\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia de innovaci\u00f3n social: inclusi\u00f3n y turismo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26441\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26441\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Consolidar y fortalecer una nueva red de nodos de innovaci\u00f3n social que promueva la inclusi\u00f3n socio laboral en personas con alguna discapacidad, personas mayores, mujeres y personas en situaci\u00f3n de vulnerabilidad enfocada en los sectores econ\u00f3micos priorizados en la Estrategia de Desarrollo Regional 2011-2020 (EDRE) y de innovaci\u00f3n, priorizando el sector tur\u00edstico, y agroalimentario y la puesta en valor de la identidad cultural.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2023 - Diciembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26582\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Educaci\u00f3n estad\u00edstica c\u00edvica: una oportunidad para la articulaci\u00f3n curricular entre ciencias para la ciudadan\u00eda y matem\u00e1ticas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26582\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26582\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La estad\u00edstica es una disciplina que se encuentra presente en diferentes \u00e1reas de conocimiento,\r\ncumpliento un rol diferente en cada uno de ellas. En particular, esta disciplina forma parte de los\r\ncurr\u00edculos escolares de matem\u00e1tica, adem\u00e1s de estar presente en la formaci\u00f3n inicial de carreras\r\ncomo pedagog\u00eda en ciencias naturales y pedagog\u00eda en educaci\u00f3n b\u00e1sica. Por otro lado,\r\nactualmente, existe un consenso sobre la importancia del desarrollo de la alfabetizaci\u00f3n\r\nestad\u00edstica en el estudiantado, por su rol como una herramienta para comprender cr\u00edticamente\r\nla informaci\u00f3n estad\u00edstica presente en diferentes contextos siendo as\u00ed un elemento clave para la\r\nformaci\u00f3n ciudadana. Considerando lo anteriormente expuesto, esta propuesta tiene por\r\nobjetivo el dise\u00f1o, implementaci\u00f3n y evaluaci\u00f3n de secuencias de ense\u00f1anza y aprendizaje en el\r\nl\u00ednea de la estad\u00edstica c\u00edvica para los contextos educativos de las carreras de Pedagog\u00eda en Ciencias\r\nNaturales y Pedagog\u00eda en Matem\u00e1ticas mediante la metodolog\u00eda Investigaci\u00f3n Basada en el\r\nDise\u00f1o. En su dise\u00f1o inicial, el desarrollo de estas secuencias de ense\u00f1anza-aprendizaje busca\r\npotenciar el rol de la estad\u00edstica en la formaci\u00f3n ciudadana de futuras\/os profesoras\/es de estas\r\ncarreras. Luego de su implementaci\u00f3n, mediante un focus group con las y los estudiantes\r\nparticipantes, buscamos identificar dificultades y potencialidades de nuestro dise\u00f1o con tal de\r\nadecuarlos a los contextos educativos de formaci\u00f3n docente en el \u00e1rea de ciencias y matem\u00e1ticas.\r\nFinalmente, el producto de esta propuesta corresponde a un dossier de proyectos en la l\u00ednea de\r\nla estad\u00edstica c\u00edvica que puedan ser utilizados en diferentes asignaturas de estad\u00edstica en la\r\nEscuela de Educaci\u00f3n, as\u00ed como orientaciones para las y los docentes de la Escuela de Educaci\u00f3n\r\nrespecto a la metodolog\u00eda de Investigaci\u00f3n Basada en el Dise\u00f1o.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FIC IDI 40048442-0<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2023 - Mayo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26680\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia de innovaci\u00f3n social: inclusi\u00f3n y turismo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26680\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26680\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Consolidar y fortalecer una nueva red de nodos de innovaci\u00f3n social que promueva la inclusi\u00f3n socio laboral en personas con alguna discapacidad, personas mayores, mujeres y personas en situaci\u00f3n de vulnerabilidad enfocada en los sectores econ\u00f3micos priorizados en la Estrategia de Desarrollo Regional 2011-2020 (EDRE) y de innovaci\u00f3n, priorizando el sector tur\u00edstico, y agroalimentario y la puesta en valor de la identidad cultural.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FIC IDI 40048442-0<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2023 - Mayo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26717\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia de innovaci\u00f3n social: inclusi\u00f3n y turismo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26717\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26717\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Consolidar y fortalecer una nueva red de nodos de innovaci\u00f3n social que promueva la inclusi\u00f3n socio laboral en personas con alguna discapacidad, personas mayores, mujeres y personas en situaci\u00f3n de vulnerabilidad enfocada en los sectores econ\u00f3micos priorizados en la Estrategia de Desarrollo Regional 2011-2020 (EDRE) y de innovaci\u00f3n, priorizando el sector tur\u00edstico, y agroalimentario y la puesta en valor de la identidad cultural.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FIC IDI 40048442-0<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2023 - Mayo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26836\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia de innovaci\u00f3n social: inclusi\u00f3n y turismo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26836\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26836\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Consolidar y fortalecer una nueva red de nodos de innovaci\u00f3n social que promueva la inclusi\u00f3n socio laboral en personas con alguna discapacidad, personas mayores, mujeres y personas en situaci\u00f3n de vulnerabilidad enfocada en los sectores econ\u00f3micos priorizados en la Estrategia de Desarrollo Regional 2011-2020 (EDRE) y de innovaci\u00f3n, priorizando el sector tur\u00edstico, y agroalimentario y la puesta en valor de la identidad cultural.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FIC IDI 40048442-0<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2023 - Mayo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26951\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia de innovaci\u00f3n social: inclusi\u00f3n y turismo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26951\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26951\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Consolidar y fortalecer una nueva red de nodos de innovaci\u00f3n social que promueva la inclusi\u00f3n socio laboral en personas con alguna discapacidad, personas mayores, mujeres y personas en situaci\u00f3n de vulnerabilidad enfocada en los sectores econ\u00f3micos priorizados en la Estrategia de Desarrollo Regional 2011-2020 (EDRE) y de innovaci\u00f3n, priorizando el sector tur\u00edstico, y agroalimentario y la puesta en valor de la identidad cultural.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2023 - Junio 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27059\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Gratuidad en educaci\u00f3n superior: Efectos en la matr\u00edcula y en los resultados educacionales de los estudiantes\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27059\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27059\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Concurso RIS de Investigaci\u00f3n, Gratuidad en educaci\u00f3n superior: Efectos en la matr\u00edcula y en los resultados educacionales de los estudiantes. Investigadora responsable: Alejandra Mizala. Coinvestigadores: Catalina Canals y Pablo Carvajal.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> Fondecyt Regular 2023, N\u00b01231128<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2023 - Abril 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27116\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Mecanismos de selecci\u00f3n de casos en el proceso penal: Entre la regulaci\u00f3n y la discrecionalidad del Ministerio P\u00fablico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27116\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27116\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Principio de Oportunidad[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1230872<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2023 - Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26312\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Non-thermal technologies for Highly Hazardous Pesticides in fresh vegetables: Study of Processing factors and Risk Assessment according their Maximum Residue Levels of Chile.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26312\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26312\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]In modern agriculture the production of fresh vegetables requires the use of pesticides to control pest and\r\ndiseases during the vegetation period as pre- or post-harvest treatment. However, the improper use of\r\npesticides due to overuse, harvesting before the Pre-Harvest Interval (PHI), can lead a high number of\r\npesticides residues increasing the exposure and impacts on human health. Different scientific evidences and\r\nofficial data from the national surveillance shown that pesticides in Chile are not enough regulated and\r\nmonitored for their import, registration, agricultural and domestic use. In addition, scientific papers have\r\nshown serious concerns due to presence of Highly Hazardous Pesticides (HHPs) in highly consumed fresh\r\nvegetables in Chile from farmers, food street markets and supermarkets mainly in the Metropolitan Region.\r\nCurrently pesticide residues represent a national concern due to serious transgression of Chilean Maximum\r\nResidue Levels (MRLs) and number and concentrations of HHPs. The HHPs are acknowledged to present high\r\nlevels of acute or chronic hazards to human health and environment under the criteria of the World Health\r\nOrganization (WHO), the Food and Agriculture Organization of the United Nations (FAO), the Globally\r\nHarmonized System of Classification and Labelling of Chemical (GHS), and the international agreements or\r\nconventions (Rotterdam, Stockholm or Paris). There is a relevant need to support and provide to official\r\nauthorities with novel and high-quality information of mitigation strategies for reducing the presence of HHPs\r\nresidues in food. Also, the methodologies to obtain processing factors and to evaluate risk assessment are\r\nnecessary for modify the current regulation to restrict or ban the authorization of HHPs in Chile. On another\r\nhand, non-thermal technologies for reducing pesticide residues appears as a suitable strategy to reduce the\r\npresence of pesticide residues in fresh food. Therefore, the main objective is to study the effect of nonthermal technologies on highly hazardous pesticides residues on fresh vegetables including their associated\r\nprocessing factors and risk assessment according the Maximum Residue Levels of pesticides in Chile. Two\r\nspecific aims have been proposed; to determine the effects of non-thermal technologies on highly hazardous\r\npesticides in fresh vegetables and their corresponding processing factors and maximum residue levels; to\r\nevaluate health risk assessment of highly hazardous pesticides according the processing factors and\r\nmaximum residue levels. The method of extraction will be \"quick, easy, cheap, effective, rugged and safe\"\r\nQuEChERS for HHPs multiresidues according to the guideline SANTE 2017 provided by European Commission.\r\nThe quantification for HHPs residues in leafy vegetables (lettuce and chard) and solanaceous vegetables\r\n(tomatoes and peppers) will be using Liquid and Gas Chromatography (HPLC-MS\/MS and GC-MS\/MS) based\r\non the guideline SANTE 2017 provided by European Commission. Different parameters will be validated such\r\nas %RSD, uncertainty, limit of detection and quantification (LOD, LOQ). During the fourth year of project\r\neach season vegetables will be cultivated under good agricultural practices (GAP) in the Experimental Field\r\nTalagante at Universidad de Las Americas (UDLA). Twenty HHPs will be used for their high presence and\r\ntransgression of the Maximum Residue Levels (MRLs) of Chile at the National Surveillance of Agricultural and\r\nLivestock Services (SAG) reported in the last five years. The applications will be set up at the field rate (FR)\r\nproposed in the labelling of the products and doble field rate (2FR) to emulate the overuse of pesticides by\r\nfarmers with the purpose to have high levels of HHPs for the non-thermal technologies. The vegetables will\r\nbe transported under refrigerated conditions (-4\u00baC) to the Laboratory of Chemistry at UDLA. The non-thermal\r\ntechnologies were selected for their novelty and promising results for reducing pesticides residues: Cold\r\nPlasma, UV light, ultrasound and ozone (O3) will be used at two concentrations each one by three replicates\r\nfor each treatment\/vegetable. Controls with or without HHPs will be used to compare. After use non-thermal\r\ntechnologies, the processing factors will be determinate for each vegetable\/HHPs\/non-thermal technology.\r\nThe risk assessment will be evaluated through the estimated daily intake (EDI), the Hazard quotient (HQ)\r\nand the chronic hazard index (cHI) for each HHPs. The pesticide residue intake models will be setup using\r\ndata by the average body of Chileans, age, gender, and a mixture of data from the model PRIMo V 3.1 which\r\nis used by the European Food safety Authority (EFSA). The results of this project should be used to increase\r\nthe knowledge of non-thermal technologies to decrease the serious levels of HHps in the most consumed\r\nfresh vegetables of Chile, reduce the number of transgressions of the Chilean MRLs, and decrease the hazard\r\nof HHPs to human health. Likewise, to support the decision-making process of national authorities for the\r\nrestriction or ban of Highly Hazardous Pesticides.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1230860<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2023 - Abril 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26148\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Cazadores recolectores de la cuenca del Lago Tagua Tagua (Regi\u00f3n de O\u0092Higgins): evaluando el uso del espacio, movilidad y territorialidad entre el Pleistoceno final y el Holoceno Tard\u00edo (ca. 13000 \u0096 3000 a\u00f1os cal AP).\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26148\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26148\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Arqueolog\u00eda y Paleontolog\u00eda del antiguo Lago de Tagua Tagua[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 3230676<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2023 - Marzo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26464\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            LANDSLIDES IN CENTRAL CHILE (32.5\u00b0S \u0096 35\u00b0S): THE ROLE OF THE MEGA DROUGHT AND EARTHQUAKES IN HAZARD ASSESSMENT AND DISASTER PREVENTION\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26464\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26464\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Landslides are an important landscape forming process, providing the main mechanism for sediment release from slopes to permit transportation through the fluvial system. Thus, in advecting mountain chains, landslides play a key role in allowing the development of a long-term dynamic equilibrium between uplift and erosion, and in reducing slopes to their threshold angle. In doing so, landslides can directly impact humans. Unfortunately, fatalities and material losses caused by landslides concentrate in areas with high degrees of marginalization, which indicates that the most marginalized populations are the most prone to experience the negative effects of landslides. The total landslide death toll in Chile is 1010 between 1928 and 2017, 54% of them in Central Chile (32.5\u00b0S \u0096 35\u00b0S). A key question for the proposed research is what are the controlling factors affecting the temporal and spatial distribution of landslides in Central Chile (32.5\u00b0S-35\u00b0S)? The assessment of this question is relevant considering that landslides are an important natural hazard driven mainly by strong earthquakes and heavy rainfall, both triggers present in our country. \r\n\r\nChile is one of the most seismically active countries on Earth and strong earthquakes are often associated with a chain of cascading hazards, such as ground shaking, liquefaction, tsunamis, and coseismic landslides. In tectonically-active mountain areas, landslides are also a major cause of fatalities and economic losses during and after great magnitude earthquakes. In fact, in Chile, there are two broad types of earthquake-induced landslides: interplate\/megathrust and shallow crustal earthquakes. For example, the Mw 8.8 interplate\/megathrust Maule earthquake in 2010 with a rupture length of around 450 km produced more than 1200 landslides widely distributed between 32.5\u00b0S and 38\u00b0S. On the other hand, current climate trends and future projections show in addition to temperature rise a decrease in winter rainfall, an increase in the frequency of flood events, increased summer rainfall, and a rise in the torrential nature of storms. Indeed, precipitation has been reduced since 2010 in central Chile, with a 20-40% rainfall deficit. This period of 10 consecutive dry years has been called around the region the Mega Drought. All these environmental conditions are correlated with landslide activity in Central Chile. For the more recent example, on 30 January 2021, an intense and short rainfall, accompanied by hail, affected the Central Valley of Chile (34.4\u00b0S), producing catastrophic hail-debris flows affecting the local communities. According to official reports issued by the National Emergency Office, these hail-debris flows affected 200 people, leaving one house destroyed, 52 with significant damage, and another 20 with minor damage.\r\n\r\nIn recent years, landslide hazard and susceptibility maps have been developed mainly in metropolitan regions, nevertheless, none of them considered the evaluation of coseismic landslides. On the other hand, the occurrence of rainfall-induced landslides is poorly studied and probably underreported in Central Chile, especially in O\u0092Higgins and Maule regions. The purpose of this project is to identify the main characteristics of landslides that occur in Central Chile (32.5\u00b0-35\u00b0S), before and during a mega drought condition, in a zone affected by interplate\/megathrust and shallow crustal earthquakes. It seeks to improve the understanding of their mechanics, temporal-spatial distribution, and geological controlling factors, obtaining quantifiable inputs for the development of a methodology for landslide hazard assessment that includes coseismic landslides and the effect of megadrought applicable to urban\/territorial planning and disaster prevention strategies.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FI09<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2023 - Mayo 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Escuela de Educaci\u00f3n UOH<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26697\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Taller para desarrollar habilidades de modelaci\u00f3n matem\u00e1tica utilizando probabilidades y estad\u00edstica en el contexto de un juego de mesa\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26697\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26697\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En la formaci\u00f3n de profesores, se esperar\u00eda que el futuro profesorado modele fen\u00f3menos sociales y naturales analizando e interpretando datos mediante el uso de estad\u00edstica y probabilidades. En el \u00e1mbito escolar, se espera que los estudiantes sean capaces de construir una versi\u00f3n simplificada de un sistema presente en la realidad, para luego expresarlo de forma matem\u00e1tica. Sin embargo, en nuestra Escuela de Educaci\u00f3n, los cursos de probabilidades han sido categorizados como cr\u00edticos debido al bajo desempe\u00f1o registrado por nuestros estudiantes. \r\nEste proyecto busca dise\u00f1ar, implementar y evaluar un taller de modelaci\u00f3n matem\u00e1tica utilizando probabilidades y estad\u00edstica dirigido a estudiantes de pregrado. Investigaciones previas han propuesto metodolog\u00edas para identificar y analizar escenarios clave durante el desarrollo de un juego de mesa (denominado Camel Up) que ayudan a los estudiantes a mejorar sus aprendizajes de los conceptos principales de los cursos de probabilidades y estad\u00edstica. En este proyecto, adaptaremos la metodolog\u00eda mencionada para identificar y analizar escenarios claves de este juego de mesa con el fin de ense\u00f1ar el ciclo de modelaci\u00f3n matem\u00e1tico en un contexto de probabilidades, estad\u00edstica y simulaciones computacionales. Los an\u00e1lisis de estos escenarios ser\u00e1n registrados en un libro que ser\u00e1 el material central del taller, mientras que las simulaciones computacionales ser\u00e1n registradas en formato de video. Este taller ser\u00e1 implementado invitando a estudiantes de pregrado de la Universidad de O\u0092Higgins para luego evaluarlo mediante un focus group que nos permita obtener las valoraciones y opiniones de las participantes acerca de la utilidad del taller como herramienta para introducir el ciclo de modelaci\u00f3n matem\u00e1tica.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad Cat\u00f3lica del Maule<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26064\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Imaginarios de identidad nacional\/cultural en la literatura para las infancias y adolescencias que versiona relatos de tradici\u00f3n oral de los pueblos originarios de Chile: 2000-2022.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26064\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26064\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El presente proyecto, tiene como objetivo general analizar las caracter\u00edsticas discursivo-literarias, art\u00edsticas, editoriales y simb\u00f3lico-culturales que exhibe la configuraci\u00f3n de los imaginarios de identidad en la literatura para las infancias y adolescencias que versiona relatos de tradici\u00f3n oral de los pueblos originarios de Chile en las \u00faltimas dos d\u00e9cadas. Los objetivos espec\u00edficos contemplan identificar autores, obras, g\u00e9neros y formatos de este tipo de obras; describir las caracter\u00edsticas discursivo-literarias, art\u00edsticas y editoriales de estos relatos, e interpretar problematizadoramente sentidos sobre la configuraci\u00f3n de imaginarios de identidades.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 648531<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2023 - Noviembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de las culturas, las artes y los patrimonios<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26077\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26077\" aria-expanded=\"false\" aria-controls=\"collapse-26077\">\n                                            Laboratorio cinematogr\u00e1fico experimental para uso did\u00e1ctico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26077\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26077\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto consiste en realizar talleres de apreciaci\u00f3n y creaci\u00f3n cinematogr\u00e1ficos dirigidos a profesoras y profesores de ense\u00f1anza general b\u00e1sica a cargo de las asignaturas de artes visuales, m\u00fasica, lenguaje e Historia y a especialistas del \u00e1rea de m\u00fasica y artes de la escuela de cultura y difusi\u00f3n art\u00edstica. Esto con el prop\u00f3sito\r\nde aplicar lo aprendido en el aula con profesorado y estudiantes de cursos de 6\u00b0 a 8\u00b0 b\u00e1sico de las escuelas beneficiadas.\r\nLos talleres se relacionan con objetivos de aprendizaje de cada una de las asignaturas participantes, de modo de conectar los conocimientos y experimentaci\u00f3n cinematogr\u00e1fica con los aprendizajes escolares esperados,\r\nfacilitando as\u00ed su aplicaci\u00f3n. Los talleres se realizar\u00e1n una vez por semana en dependencias de la Escuela de Cultura y Difusi\u00f3n Art\u00edstica, tendr\u00e1n una duraci\u00f3n de tres horas. Se destinar\u00e1n 4 meses para la capacitaci\u00f3n te\u00f3rico pr\u00e1ctica y tres meses para acompa\u00f1ar la puesta en pr\u00e1ctica de la unidad planificada en los cursos\r\nde los distintos establecimientos y posteriormente evaluar los resultados y realizar una muestra de los trabajos realizados.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2023 - Marzo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26157\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Motivational factors associated with reading comprehension: role of intrinsic motivation and self-efficacy perception during teaching-learning processes\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26157\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26157\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Hypotheses: 1) There is a significant relationship between a) dimensions of reading motivation, b) strategies to teach reading, and c) reading performance of adolescent students. 2) Teachers whom foster reading motivation have a repertoire of teaching strategies directly associated with it. In sum, the general objective of this proposal is to analyze the relationship between reading competence, intrinsic motivation, and self-efficacy perception, and to analyze the characteristics of the didactic strategies that can promote the motivation associated with reading.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2023 - Marzo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26570\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Motivational factors associated with reading comprehension: role of intrinsic motivation and self-efficacy perception during teaching-learning processes\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26570\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26570\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Hypotheses: 1) There is a significant relationship between a) dimensions of reading motivation, b) strategies to teach reading, and c) reading performance of adolescent students. 2) Teachers whom foster reading motivation have a repertoire of teaching strategies directly associated with it. In sum, the general objective of this proposal is to analyze the relationship between reading competence, intrinsic motivation, and self-efficacy perception, and to analyze the characteristics of the didactic strategies that can promote the motivation associated with reading.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1230762<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2023 - Marzo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26736\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Diferencias sexuales en condicionamiento cl\u00e1sico \u00bfDimorfismo en Aprendizaje o Conducta?\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26736\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26736\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetivo general del proyecto en sus tres l\u00edneas de investigaci\u00f3n con animales es comprobar la existencia de\r\ndiferencias sexuales en tres paradigmas de condicionamiento cl\u00e1sico, a saber, aversi\u00f3n condicionada al sabor,\r\ncondicionamiento del miedo y aprendizaje apetitivo. Se utilizar\u00e1n estos tres paradigmas a fin de establecer si el\r\npotencial dimorfismo sexual (para el que existen algunas recientes evidencias) se refiere a mecanismos de\r\naprendizaje o a la manifestaci\u00f3n conductual del aprendizaje. Adem\u00e1s de responder a esta importante pregunta de\r\ninvestigaci\u00f3n, dilucidar la existencia de dimorfismo en cada uno de estos paradigmas es relevante en si mismo y\r\ntiene importantes implicaciones cl\u00ednicas en lo que respecta al comportamiento alimentarios, la etiolog\u00eda y\r\ntratamiento de problemas de salud mental relacionados con el miedo y la ansiedad, entre otros.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2023 - Marzo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26784\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Motivational factors associated with reading comprehension: role of intrinsic motivation and self-efficacy perception during teaching-learning processes\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26784\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26784\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Hypotheses: 1) There is a significant relationship between a) dimensions of reading motivation, b) strategies to teach reading, and c) reading performance of adolescent students. 2) Teachers whom foster reading motivation have a repertoire of teaching strategies directly associated with it. In sum, the general objective of this proposal is to analyze the relationship between reading competence, intrinsic motivation, and self-efficacy perception, and to analyze the characteristics of the didactic strategies that can promote the motivation associated with reading.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> UCV20101<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2023 - Diciembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Programa de Proyectos de Mejoramiento, Innovaci\u00f3n e Investigaci\u00f3n de la Docencia Universitaria PUCV<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27022\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Del feedback al feedforward: escritura acad\u00e9mica en Ciencias\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27022\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27022\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La alfabetizaci\u00f3n en retroalimentaci\u00f3n es un campo cada vez m\u00e1s explorado por la importancia que posee. Sin embargo, aunque hay iniciativas que promueven la escritura acad\u00e9mica y su retroalimentaci\u00f3n en la formaci\u00f3n universitaria, se presta menos atenci\u00f3n a c\u00f3mo los estudiantes incorporan los comentarios de retroalimentaci\u00f3n en futuras tareas. El prop\u00f3sito de este proyecto es examinar c\u00f3mo estudiantes de Pedagog\u00eda en Educaci\u00f3n B\u00e1sica de una universidad chilena asimilan la retroalimentaci\u00f3n al resolver un Aprendizaje Basado en Problemas (ABP). Se explora la escritura de un Informe de resoluci\u00f3n de problemas (IRP) como forma de comunicar los aprendizajes del ABP, pues implica desarrollar habilidades como la indagaci\u00f3n, la formulaci\u00f3n de preguntas de investigaci\u00f3n, el an\u00e1lisis cr\u00edtico de fuentes y el trabajo colaborativo. A partir de una intervenci\u00f3n did\u00e1ctica en la elaboraci\u00f3n de IRP se analizan comentarios de los profesores para determinar si se centran solo en la retroalimentaci\u00f3n (feedback) o tambi\u00e9n ofrecen orientaci\u00f3n futura (feedforward). Asimismo, se abordan las percepciones de los estudiantes con respecto a la formaci\u00f3n recibida.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2023 - Abril 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>SOCHINUT<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27083\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            No Whey: L\u00e1cteos altos en prote\u00edna y ejercicio de resistencia para la mejora de la composici\u00f3n corporal y funci\u00f3n muscular de personas mayores\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27083\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27083\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"].[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 123036<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2023 - Abril 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27127\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Worlds of Algae: Exploring the emergence of marine transition experiments in Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27127\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27127\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]One of the most urgent socio-environmental crises facing humanity is the massive deterioration of\r\nearth's ecosystems. The scale of this process is so vast that there is talk that we are living through the\r\nsixth mass extinction of species, leaving no ecosystem worldwide unaffected. Although when thinking\r\nabout these processes we tend to concentrate on land-based ecosystems, marine ecosystems are also\r\nexperiencing massive degradation processes. Human-induced phenomena such as ocean warming,\r\nextensive pollution, acidification and deoxygenation, are causing ecological struggles everywhere. In\r\nparallel, the relentless extraction and ubiquitous pollution associated with industries such as fishing and\r\naquaculture have also become a leading cause of marine environmental degradation.\r\nGiven its extensive coastline and the massive scale of its fishing and aquaculture industries, Chile is\r\nvery much at the center of such processes of anthropogenic marine degradation. Such decay does not only\r\naffect the nonhuman component of marine ecosystems \u0096 with some studies estimating that 2\/3 of the\r\ncountry\u0092s fisheries have been heavily affected \u0096 but also the human groups depending on them, especially\r\nhundreds of low-income fishing communities all over the country. The recognition of this degradation is not\r\nnew, motivating since mid-1990s different kinds of public and private interventions to turn marine-based\r\nindustries towards sustainability. So far, these interventions have been mostly ineffective, mainly because\r\nthey have taken an incremental approach to the issue, not really challenging the roots of the systems of\r\nextractivism that allow ever-growing levels of environmental damage and injustice.\r\nThe leading hypothesis of this research project is that a new kind of transition project is\r\nslowly emerging in the Chilean marine productive sector. Following the relevant literature on\r\nsustainability transitions in the fields of political ecology, science and technology studies (STS) and\r\nmultispecies studies, this project will see these marine transition experiments (MTE) as aiming to\r\nenhance the sustainability of the marine productive sector through an experimental redefinition\r\nof the identities and relationships among some of its leading components. In particular, the\r\nproject will focus on three components these experiments usually aim to redefine (with variable\r\nintensities): (1) its social component, towards a more nuanced understanding of the socioeconomic,\r\npolitical and cultural complexities involved in transition processes, (2) its epistemic component, towards a\r\nholistic approach to knowledge production and circulation, and (3) its nonhuman component, towards a\r\ncommitment to respect and protect the involved nonhuman biological entities.\r\nIn order to empirically explore the specific contours and challenges that such MTEs are facing in\r\nChile this research project will engage with experiments focused on a particularly central component of\r\nmarine ecologies: macroalgae. Although a key component of most marine ecosystems in the country, an\r\nongoing boom on its extraction \u0096 that has turned Chile into one of its leading exporters worldwide \u0096 has\r\ncaused massive damage to several key macroalgae ecosystems, and the multiple beings that depend on\r\nthem. Reacting to this situation, in recent years a series of initiatives much closer to the MTE model have\r\nemerged on this area, projects that can be divided on two main types. First, there are MTE focused on\r\ndomestication, referring to initiatives that aim at replacing the direct extraction of macroalgae from the\r\nseabed by its careful and continual cultivation and harvesting. Second, and reacting to the current model\r\nbased on the export of macroalgae as raw material, there are MTE focused on potentiation, or initiatives\r\naiming at locally processing macroalgae in order to potentiate one particular strain or process, turning it\r\ninto elaborated products or components of technical processes.\r\nThe general objective of this research project will be to explore using a transdisciplinary social\r\nscience approach the emergence of MTEs centered in the macroalgae industry in Chile, putting a\r\nspecific focus on the barriers and frictions they are currently facing and exploring novel ways to enhance\r\ntheir potential. In empirical terms, this exploration will be based on the development of case studies of\r\nongoing domestication and potentiation MTEs. In each of these cases, multispecies ethnography will be\r\nmixed with action-research initiatives, so as not only to describe and analyze in a dense transdisciplinary\r\nway the issues and opportunities arising from these initiatives, but also to collaborate with multiple publics\r\non sketching possible ways on which they could be strengthened. Selecting concrete case studies in\r\ndifferent locations at a national level, the project will produce and disseminate highly innovative knowledge\r\nregarding the barriers and challenges faced by ongoing MTEs, with the final aim of contributing to the\r\nurgent need to move towards more sustainable productive engagements with marine ecosystems.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1231401<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2023 - Marzo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26130\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Capillary networks, gel debonding in prostheses, and fracture in rock mining from the viewpoint of the mathematical analysis of free-discontinuity problems\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26130\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26130\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]One goal is to enhance the methods being currently developed by Esp&#305;&#769;ndola (Physics), Krause (Physiology), and Xavier (Biomedical Engineering) for reconstructing capillary networks with ultrasound. The super-resolution is needed for early detection diseases such as cognitive decline, cancer, or liver fibrosis. They perfuse lipid-encapsulated microbubbles as contrast agents and then localize the bubbles in the ultrasound images with the singular value filter. However, that method leaves a non-negligible percentage of bubbles undetected. Here we propose to complement the singular value filter for the detection and tracking of microbubbles with the sophisticated and mathematically sound Mumford-Shah method for image contour detection, which stems from the conceptually-insightful and numerically-robust perspective of the minimization of energies. In the reconstruction of the capillary network from ultrasound, it is impossible to directly distinguish the microbubbles, or even the blood vessels, in each frame separately, due to the attentuation and degradation in this imaging technique. It is essential to take into account the dynamic nature of the problem, distinguishing the slowly-varying signals emitted by the tissue from those emitted by the microbubbles, which flow rapidly, behave nonlinearly, and have a much shorter coherence length. We therefore propose to regard the collection of two-dimensional frames as a single three-dimensional image, where a moving bubble becomes a tubular neighbourhood of a filament, which the Mumford-Shah model is expected to recover. From these filaments, bubbles can be detected and tracked, and the vertical inclinations of theses filaments will yield the microbubbles velocities. From the velocity profiles it is possible to estimate the shear wall stresses (their \u0091tangential elastic rigidities\u0092) of the blood vessels, and anomalies in these stresses are commonly good indicators of the presence of specific diseases. \r\n A fortunate encounter between mathematics and mechanics led to the observation that the problem of\r\nfinding the path that the propagation of a crack will follow inside a structure upon loading could be solved with the mathematical theory (the analysis of free-discontinuity problems) developed for the apparently unrelated image segmentation Mumford-Shah model. The variational fracture theory initiated by Francfort and Marigo is by now (20 years after) very well established. The second goal of this proposal is to further develop the ongoing collaboration between Song (Pharmaceutics), Siegel (Pharmaceutics), S\u00e1nchez (Numerical analysis), Calderer (Applied mathematics), and the PI on the study of the debonding of polymer gels from rigid substrates (relevant in the design of the synthetic polymers coating the metallic parts of pacemakers and other medical prostheses) from this variational fracture theory perspective.\r\n The third main goal is to apply the mathematical analysis of free-discontinuity problems to the modelling of the evolution of the cavity in the block caving technique in underground rock mining. This has been pursued by Ortega, Lecaros, and coworkers from the side of applied mathematics in academia, in collaboration with Gaete from the Geomechanics Research Department at El Teniente, research group to which Guti\u00e9rrez and the PI have joined in the last months. We propose to study the seismic activity induced by the fracture of the rock mass due to gravity, following the works in the last decade within the variational fracture theory that incorporate the inertia e&#64256;ects. The final aim is to optimize the injection of water jets for the aminoration of the seismic events near the operation sites.\r\n The three research lines are applications of the phase-field regularization by Ambrosio and Tortorelli of the Mumford-Shah free-discontinuity model, a di&#64256;erent variant being required in each of the three contexts. The first stage of the implementation is of mathematical modelling and high-level numerical simulation abilities, in which the intuition and first-hand knowledge from the members of the research team that are experts in vascular function, ultrasound imaging, polymer chemistry, and mining geomechanics is translated into particular mathematical concepts and concrete computational methods. This is followed by a stage of calibration and validation, where the full interplay with experiments is required. The product of a robust and validated computational method will constitute then an advancement in the capabilities, available resources, and understanding in each of the applied disciplines.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1230195<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2023 - Marzo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26264\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            BCL6: a new transcription factor regulating cardiomyocyte hypertrophy in rat and human models.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26264\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26264\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Materia investigada: Biomedicina, enfermedades cardiovasculares, regulaci\u00f3n transcripcional.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1230194<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2023 - Marzo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26268\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            The methylome transcriptional regulatory network activated by copper in Enterococcus faecalis.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26268\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26268\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Materia investigada: Regulaci\u00f3n transcripcional, microbiolog\u00eda, metilaciones, cobre.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1231401<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2023 - Marzo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26293\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Capillary networks, gel debonding in prostheses, and fracture in rock mining from the viewpoint of the mathematical analysis of free-discontinuity problems\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26293\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26293\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]One goal is to enhance the methods being currently developed by Esp&#305;&#769;ndola (Physics), Krause (Physiology), and Xavier (Biomedical Engineering) for reconstructing capillary networks with ultrasound. The super-resolution is needed for early detection diseases such as cognitive decline, cancer, or liver fibrosis. They perfuse lipid-encapsulated microbubbles as contrast agents and then localize the bubbles in the ultrasound images with the singular value filter. However, that method leaves a non-negligible percentage of bubbles undetected. Here we propose to complement the singular value filter for the detection and tracking of microbubbles with the sophisticated and mathematically sound Mumford-Shah method for image contour detection, which stems from the conceptually-insightful and numerically-robust perspective of the minimization of energies. In the reconstruction of the capillary network from ultrasound, it is impossible to directly distinguish the microbubbles, or even the blood vessels, in each frame separately, due to the attentuation and degradation in this imaging technique. It is essential to take into account the dynamic nature of the problem, distinguishing the slowly-varying signals emitted by the tissue from those emitted by the microbubbles, which flow rapidly, behave nonlinearly, and have a much shorter coherence length. We therefore propose to regard the collection of two-dimensional frames as a single three-dimensional image, where a moving bubble becomes a tubular neighbourhood of a filament, which the Mumford-Shah model is expected to recover. From these filaments, bubbles can be detected and tracked, and the vertical inclinations of theses filaments will yield the microbubbles velocities. From the velocity profiles it is possible to estimate the shear wall stresses (their \u0091tangential elastic rigidities\u0092) of the blood vessels, and anomalies in these stresses are commonly good indicators of the presence of specific diseases. \r\n A fortunate encounter between mathematics and mechanics led to the observation that the problem of\r\nfinding the path that the propagation of a crack will follow inside a structure upon loading could be solved with the mathematical theory (the analysis of free-discontinuity problems) developed for the apparently unrelated image segmentation Mumford-Shah model. The variational fracture theory initiated by Francfort and Marigo is by now (20 years after) very well established. The second goal of this proposal is to further develop the ongoing collaboration between Song (Pharmaceutics), Siegel (Pharmaceutics), S\u00e1nchez (Numerical analysis), Calderer (Applied mathematics), and the PI on the study of the debonding of polymer gels from rigid substrates (relevant in the design of the synthetic polymers coating the metallic parts of pacemakers and other medical prostheses) from this variational fracture theory perspective.\r\n The third main goal is to apply the mathematical analysis of free-discontinuity problems to the modelling of the evolution of the cavity in the block caving technique in underground rock mining. This has been pursued by Ortega, Lecaros, and coworkers from the side of applied mathematics in academia, in collaboration with Gaete from the Geomechanics Research Department at El Teniente, research group to which Guti\u00e9rrez and the PI have joined in the last months. We propose to study the seismic activity induced by the fracture of the rock mass due to gravity, following the works in the last decade within the variational fracture theory that incorporate the inertia e&#64256;ects. The final aim is to optimize the injection of water jets for the aminoration of the seismic events near the operation sites.\r\n The three research lines are applications of the phase-field regularization by Ambrosio and Tortorelli of the Mumford-Shah free-discontinuity model, a di&#64256;erent variant being required in each of the three contexts. The first stage of the implementation is of mathematical modelling and high-level numerical simulation abilities, in which the intuition and first-hand knowledge from the members of the research team that are experts in vascular function, ultrasound imaging, polymer chemistry, and mining geomechanics is translated into particular mathematical concepts and concrete computational methods. This is followed by a stage of calibration and validation, where the full interplay with experiments is required. The product of a robust and validated computational method will constitute then an advancement in the capabilities, available resources, and understanding in each of the applied disciplines.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2023 - Marzo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26294\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Plate and shell models for magnetoelastic and poroelastic heterogeneous materials and modeling for a gel bonded to a curved rigid substrate obtained by simultaneous homogenization and dimension reduction\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26294\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26294\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Our interest in this project is to obtain two-dimensional models for a three-dimensional thin structures involving situations:\r\n\u0095 Magnetoelastic plates which are heterogeneous and whose heterogeneity occur at a small scale which depends of the thickness of the plate. Depending on energy scaling and the ratio between these two small parameters, different theories can be obtained.\r\n\u0095 Poroelastic shell containing a viscous fluid.\r\n\u0095 Quasistatic evolution problems for linearly elastoplastic shell with hardening.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Patrocinante<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2023 - Marzo 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26511\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Interdisciplinary study on the perception of noise in the city of Santiago in the (post)pandemic context\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26511\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26511\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]This research project aims to answer the following question: How is people\u0092s perception of noise related to the socioeconomic, urban, and environmental characteristics of their neighborhoods in the (post)pandemic context? This project seeks to contribute to noise and urban knowledge from an interdisciplinary approach at the intersection between geography, sociology, urban planning and acoustic engineering. It is thus articulated around four specific objectives (SO): SO1) to analyze the relationship between noise complaints and demographic, socioeconomic, urban and environmental variables in 6 municipalities of Santiago; SO2) characterize noise annoyance and strategies adopted by the inhabitants of 6 socioeconomically diverse neighborhoods with different exposure to noise; SO3) to evaluate the soundscapes of 6 neighborhoods; SO4) To propose guidelines for integrating the perception of noise in public policies related to noise and in urban planning.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> R01EY034615<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>NIH National Eye Insitute<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26537\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            The role of heme in retinal vascular development and disease\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26537\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26537\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Retinal vascular diseases are major causes of vision loss in the United States and around the world. To better treat these disorders, we need to understand the signaling pathways that control the growth and integrity of retinal blood vessels. Our recent publications and preliminary data detail a novel angiogenic signaling system centered around heme, a co-factor critical for oxygen transport, metabolism, and gene transcription. We found that heme promotes angiogenic growth in the retina by regulating tip\/stalk selection, and that reduced heme production or import leads to reduced retinal vascularization and tissue hypoxia, similar to other retinal vasculopathies including retinopathy of prematurity, choroidal neovascularization, and the rare but important exudative vitreoretinopathies. Furthermore, we found that VEGF suppresses, while Norrin-bCatenin promotes, the expression of the obligate endothelial heme importer, Flvcr2.  Based on these data, we hypothesize that heme, is involved in retinal angiogenesis and retinal vasculopathies. The Specific Aims of this proposal are to (1) determine how heme intersects with Notch signaling to control angiogenic tip\/stalk selection, (2) characterize the role for Flvcr2\/heme in VEGF-induced angiogenic proliferation and neo-vascularization, and (3) determine whether induction of Flvcr2\/heme signaling is sufficient and necessary to reverse the vascular defects and downstream vision changes observed in mouse models of exudative vitreoretinopathy. To accomplish these aims, we developed new tools to directly manipulate heme in cultured retinal endothelial cells and assess heme transport and intracellular trafficking in vitro. We also generated new conditional knock-in and knock-out alleles to manipulate endothelial heme transport in vivo. Our studies will fundamentally impact our understanding of how endothelial heme levels are controlled, and the role of heme in retinal angiogenesis and vascular disease.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FONDECYT Regular n\u00b01231930<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2023 - Abril 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27060\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Segregaci\u00f3n de G\u00e9nero entre \u00e1reas de conocimiento en la educaci\u00f3n media\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27060\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27060\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En Am\u00e9rica Latina y el Caribe, las inequidades de g\u00e9nero persisten en, y a trav\u00e9s de, la educaci\u00f3n, modelando las trayectorias de vida de ni\u00f1as\/os, j\u00f3venes, mujeres y hombres de manera desigual, e impactando en el desarrollo sostenible de la regi\u00f3n. En Chile, si bien se ha avanzado en la reducci\u00f3n de brechas de g\u00e9nero en a\u00f1os de escolaridad, existe una fuerte segregaci\u00f3n de g\u00e9nero entre \u00e1reas del conocimiento en la educaci\u00f3n superior y entre ocupaciones. Esta segregaci\u00f3n horizontal, que genera brechas en oportunidades sociales y condiciones laborales entre hombres y mujeres, tiene sus ra\u00edces en procesos de socializaci\u00f3n tempranos, y los sistemas educativos son fundamentales en su desarrollo y reproducci\u00f3n a lo largo de la vida.\r\n\r\nSustentado en una perspectiva de g\u00e9nero y un enfoque del curso de la vida, el presente proyecto busca desarrollar una agenda de investigaci\u00f3n interdisciplinaria sobre segregaci\u00f3n horizontal temprana en Chile, as\u00ed como sobre sus antecedentes, moderadores y consecuencias. Para esto, se estudiar\u00e1n los patrones generizados de elecci\u00f3n de cursos electivos de ense\u00f1anza media cient\u00edfico-humanista, identificando diferencias entre y dentro de \u00e1reas del conocimiento, con foco en: 1) su estabilidad durante el per\u00edodo 2011-2022; 2) su consistencia entre establecimientos, de diversa dependencia administrativa, ubicaci\u00f3n geogr\u00e1fica y composici\u00f3n (socio-econ\u00f3mica, acad\u00e9mica y de g\u00e9nero); 3) el rol de otros significativos (padres y apoderados, docentes y pares) en estas elecciones; 4) los principales moderadores a nivel de estudiante, aula\/docente y establecimiento escolar; y 5) su influencia en las transiciones a la educaci\u00f3n superior. Lo anterior, en el contexto de un sistema escolar altamente privatizado y socio-econ\u00f3micamente segregado; de la desigual implementaci\u00f3n de una reforma curricular, a partir del a\u00f1o 2020, destinada a\r\nampliar y estandarizar la variedad de cursos electivos disponibles entre escuelas; y de los efectos diferenciados de la crisis sanitaria por COVID-19 en la provisi\u00f3n de educaci\u00f3n, que han ampliado las brechas socioecon\u00f3micas y geogr\u00e1ficas en resultados educativos, debido al extenso per\u00edodo de cierre de las escuelas y al diferencial acceso y experiencias de educaci\u00f3n remota. Se analizar\u00e1 en qu\u00e9 medida estas caracter\u00edsticas y cambios estructurales del sistema educativo interact\u00faan con las diferencias de g\u00e9nero en las preferencias y elecciones de los estudiantes.\r\nMediante an\u00e1lisis de datos secundarios (bases de datos administrativas y de evaluaciones estandarizadas de cobertura censal); la aplicaci\u00f3n de cuestionarios, en dos ocasiones de medici\u00f3n, a estudiantes de ense\u00f1anza media; y la integraci\u00f3n de t\u00e9cnicas de an\u00e1lisis estad\u00edstico avanzadas (que incluyen an\u00e1lisis de datos longitudinales, modelos multinivel, an\u00e1lisis de clases latentes y an\u00e1lisis de redes sociales), el proyecto generar\u00e1 evidencia para comprender los mecanismos sociales a trav\u00e9s de los cuales el g\u00e9nero afecta las trayectorias educativas. As\u00ed, se espera contribuir al dise\u00f1o de pol\u00edticas p\u00fablicas orientadas a reducir las brechas de g\u00e9nero en oportunidades de aprendizaje y en las trayectorias educativas y laborales.\r\n\r\nLos resultados esperados del proyecto son: 1) publicar art\u00edculos en revistas de corriente principal, 2) diseminar resultados en circuitos nacionales e internacionales, 3) fortalecer la capacidad de investigaci\u00f3n educacional con perspectiva de g\u00e9nero, incorporando investigadoras j\u00f3venes y formando a estudiantes y asistentes de investigaci\u00f3n, 4) promover una perspectiva interdisciplinaria y un enfoque del curso de la vida para el estudio del rol del g\u00e9nero en educaci\u00f3n, 5) establecer una red de colaboraci\u00f3n con investigadores internacionales, e 6) identificar relaciones causales, pol\u00edticas relevantes y buenas pr\u00e1cticas que puedan ser transferidas.\r\n\r\nEl proyecto constituye un aporte novedoso al estudio del rol del g\u00e9nero en las trayectorias educativas en Chile. El equipo de investigadoras tiene vasta experiencia en investigaci\u00f3n y en la aplicaci\u00f3n de m\u00e9todos cuantitativos avanzados para responder a preguntas sustantivas sobre equidad y efectividad en educaci\u00f3n.\r\nNuestra colaboraci\u00f3n previa, as\u00ed como nuestra formaci\u00f3n disciplinar complementaria, dar\u00e1n sinergia y viabilidad al presente proyecto.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1230938<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2023 - Marzo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27070\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            IN SITU MONITORING OF PLASTIC DEFORMATION OF HIGH ENTROPY ALLOYS USING ULTRASOUND\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27070\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27070\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]It is proposed to assess the feasibility of using ultrasound as a nonintrusive, in-situ, probe of plastic behavior\r\nin high-entropy alloys (HEAs). More specifically, whether it is possible to use ultrasound to reliably\r\ncharacterize the plasticity deformation mechanism---slip, TWIP, TRIP---of Fe80-xCo10Cr10Mnx. To this end,\r\nthe speed of sound will be measured, continuously, as a function of applied stress in uniaxial tensile tests.\r\nIn previous work, proposers have shown that the speed of sound as a function of stress provides a reliable\r\ntool to measure dislocation density in aluminum, copper, and stainless steel. In the latter case, it has also\r\nbeen shown to reliably discriminate between slip and twinning as a deformation mechanism. It is now\r\nproposed to study the possibility of extending this capability not only to new materials, HEAs, but also to a\r\nnew mechanism, phase transformation.\r\nWe will start with the materials whose plastic deformation is slip-dominated, since we have robust experience\r\nin this case. We shall then move to the TWIP material, where our more recent experience will be brought to\r\nbear, to end up with the unexplored, from the point of view of ultrasound, TRIP material. Samples for tensile\r\nloading will be prepared. They will be tested using a universal testing machine and ultrasound measurements\r\nof longitudinal wave velocity will be carried out in-situ. A decrease in the wave velocity as a function of\r\napplied stress will indicate a proliferation of dislocations; the dislocation density will be determined as a\r\nfunction of stress as will the parameters of Taylor's rule. An increase in wave velocity as a function of stress\r\nwill indicate a decrease in average grain size. Modeling will be applied to determine whether this is due to\r\ntwinning or phase transformation. These results will also be validated with post-mortem XRD, TEM, and\r\nmetallography measurements, as well as ex-situ acoustic measurements.\r\nThe success of the proposed research would have short-term and long-term benefits: In the short term it\r\nwould provide a non-intrusive tool---ultrasound---to assist in the search for HEAs with pre-determined\r\nproperties, as needed for specific applications. In the long-term, it would pave the way for the development\r\nof a practical, non-intrusive, tool for the evaluation of HEA pieces in service.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11230891<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2023 - Marzo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26507\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fondecyt de Iniciaci\u00f3n 11230891 Conservation paleobiology in central Chile: merging the fossil record and ecological modeling to inform the present and future of an endangered ecosystem.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26507\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26507\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Conservation paleobiology deals with the use and application of paleontological data to the conservation of biodiversity. It implies the study of the circumstances driving species to the brink of extinction, to go extinct, or survive through the changes. In the present scenario of Global Change, this discipline seems useful as it can inform about the paths that species can undergo at present and in the near future. Particularly important to inform the state and faith of present-day ecosystems are those studies dealing with the last glacial-interglacial transition, since they show the changes faced by many still extant species under a scenario of global warming and an increasing human population. A close parallel to today\u0092s threats to biodiversity. The present proposal will use the rich vertebrate fossil record from the site of Tagua Tagua 3 (TT3) in the Antiguo Lago de Tagua Tagua (ALTT), Region de O\u0092Higgins, to investigate changes in biological communities through time. This record spans from the late Pleistocene (~13 kyr BP) to the mid Holocene (~6 kyr BP), presenting a continuous faunal sequence with extinct megafauna in its older component and extant vertebrates towards the Holocene. The record also attests the arrival and establishment of humans, as well as the occurrence of important changes in vegetation and climate. All this together makes of TT3 a unique record for central Chile, that offers the opportunity to make an adequate reconstruction of the recent past of a greatly endangered natural system. The ecosystem-through-time reconstruction and analysis includes the following objectives: (1) a comprehensive study of the fossil record to identify what, how many, and how abundant were the different species at different moments through time in the ALTT, with a particular emphasis on vertebrates; (2) to see how the communities reconstructed from the fossil record behave in moments of major environmental changes, including anthropogenic drivers of change, extinction of megafauna, and vegetation changes; (3) use food web modeling for analyzing the causes and consequences of the changes in these communities. This aims to pursue models that can integrate the fossil record and proxies of environmental change to understand the vulnerabilities to which these communities were exposed at different moments through time; (4) work in characterizing the present-day state of the vertebrate community in the area near the ALTT, aiming to build a modern picture in terms of community composition as well as in food web structure, to compare with what is revealed, and predicted, by the fossil record and associated models. The methodology to accomplishing these objectives includes: (1) fossil preparation, taxonomic identification, and quantification (MNI, NISP) for each level excavated in TT3; (2) to compare the faunal communities inferred from the fossil record to the available record of environmental changes through time (vegetation, climate, human arrival); (3) to stablish trophic relationships among the different species identified in the fossil record (using literature, stable isotope analyses results and zooarchaeological studies); this information will be used to implement food web models that explore the stability and complexity of different vertebrate communities through time and during times of particular important changes such as megafaunal extinctions, human arrival a changes in vegetation; (4) current species occurrences in the area will be inferred from the literature, open databases (GBIF) and complemented using species distributions models along with field species surveys; this information will be used to understand the current species composition of the area and to model current trophic interactions to compare with the ones inferred from the fossil record.\r\nSome expected results are a thorough characterization of community composition and food web topology through time, particularly at moments of important environmental changes. The arrival of humans during the late Pleistocene and the trophic connections generated with the fauna present should have an effect in the topology and stability of the food web. At the same time, the inclusion of a dynamic bottom-up controlled change (forested vs. shrubland) will provide important insights on how the food web and the vertebrate communities changed in moments of major vegetation changes. It is expected that some moments in the past will parallel the present-day conditions of biological systems from central Chile, providing clues on how to face the current environmental changes that endanger these ecosystems.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26065\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Paisaje y geograf\u00eda en la narrativa para las infancias en Chile: imaginarios de identidad nacional\/regional (2011-2022)-FONDECYT INICIACI\u00d3N\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26065\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26065\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Esta investigaci\u00f3n propone analizar la configuraci\u00f3n discursiva de idearios de identidad nacional y regional en un Esta investigaci\u00f3n propone analizar la configuraci\u00f3n discursiva de idearios de identidad nacional y regional en un corpus de narrativa producida espec\u00edficamente para las infancias en Chile, el cual se constituye de cuentos, novelas y libros \u00e1lbum. La cuesti\u00f3n de la identidad es un fen\u00f3meno discursivo que ha resultado ser objeto de estudio en el \u00e1mbito de la literatura para adultos\/as producida en Chile, principalmente, en las \u00faltimas tres d\u00e9cadas (Yankas; Antillanca y Lonc\u00f3n; Rojo et al.; Salomone et al.; Subercaseaux; Romero; \u00c1lvarez; Traverso y Kottow, entre otros\/as). De manera similar, se observa un inter\u00e9s en este fen\u00f3meno en el \u00e1mbito de los children\u0092s literature studies desarrollados en los \u00faltimos veinte a\u00f1os en Norteam\u00e9rica y Europa principalmente (Ying-yu Chen; McGillis; Meek; Bradford; Stephens; Doughthy; Panau y Tsilimeni; Jones; Keane; Truglio; Kelen y Sundmark). Por el contrario, en Chile, en lo que respecta a la llamada literatura infantil, el fen\u00f3meno de las discursividades sobre lo identitario es una l\u00ednea de investigaci\u00f3n incipiente (Ibaceta; Sep\u00falveda y Astudillo; Valenzuela et al.).\r\nEn consecuencia, la pertinencia de este proyecto radica en esta falta de conocimiento de un fen\u00f3meno que hist\u00f3ricamente se ha configurado discursivamente de la mano de la producci\u00f3n cultural y literaria, en parte, gracias al establecimiento de las ideolog\u00edas nacionalistas que fueron predominantes en el campo pol\u00edtico y cultural a partir del siglo XIX y durante todo el siglo xx (Cid xviii). Esta predominancia se vincula, adem\u00e1s, con procesos hist\u00f3ricos que determinan en importante medida el contexto actual y, por tanto, las l\u00f3gicas de los discursos literarios para las ni\u00f1eces. A saber, procesos hist\u00f3ricos de larga data como el colonialismo, el mestizaje, la constituci\u00f3n de un estado-naci\u00f3n, los movimientos migratorios, los procesos modernizadores y el consecuente extenso conflicto del Estado de Chile con los pueblos originarios, han infundido particularidades est\u00e9ticas e ideol\u00f3gicas en la creaci\u00f3n literaria para las infancias; particularidades que adem\u00e1s se relacionan, en las dos primeras d\u00e9cadas del siglo XXI, con fen\u00f3menos como la globalizaci\u00f3n y la crisis medioambiental, todo ello cristalizado a partir de la configuraci\u00f3n discursiva del topos (Ibaceta 2014). \r\nConsiderando esta tendencia a la articulaci\u00f3n cronot\u00f3pica del discurso identitario en la narrativa para las infancias de las \u00faltimas dos d\u00e9cadas, y con el inter\u00e9s de aportar al desarrollo del conocimiento de esta \u00e1rea a trav\u00e9s de una investigaci\u00f3n que ponga en relaci\u00f3n los resultados con el contexto sociocultural y pol\u00edtico del siglo XX y XXI, este proyecto tiene como objetivo general: Identificar, analizar y problematizar los modos de representaci\u00f3n\/construcci\u00f3n est\u00e9tico-narrativos y est\u00e9tico-gr\u00e1ficos (ilustraciones) de sentidos identitarios en un corpus de narrativas para infancia publicadas en Chile entre 2011 y 2022. Los objetivos espec\u00edficos proponen a) Analizar la construcci\u00f3n simb\u00f3lica textual del paisaje\/territorio en tanto espacio cultural, temporal y pol\u00edticamente determinado, que permite articular, perpetuar y\/o modificar imaginarios identitarios; b) Analizar la construcci\u00f3n simb\u00f3lica gr\u00e1fica (ilustraciones) del paisaje\/territorio en tanto espacio cultural, temporal y pol\u00edticamente determinado, que permite articular, perpetuar y\/o modificar imaginarios identitarios; c) Establecer y analizar la red de relaciones existentes\/posibles entre los discursos identitarios del corpus y su campo literario y cultural m\u00e1s pr\u00f3ximo (narrativas de periodos previos, discurso historiogr\u00e1fico y vinculaci\u00f3n con las lecturas sugeridas por el Ministerio de Educaci\u00f3n).\r\nEsta propuesta investigativa se sustenta sobre perspectivas te\u00f3ricas ligadas al postcolonialismo, la imagologie, el anticolonialismo latinoamericano y los landscape studies, as\u00ed como tambi\u00e9n sobre los desarrollos de los children\u0092s literature studies, particularmente en su amplia discusi\u00f3n en torno a teor\u00edas sobre los discursos gr\u00e1ficos (picture-books studies). En t\u00e9rminos metodol\u00f3gicos, para establecer las variables de an\u00e1lisis del discurso textual y gr\u00e1fico del corpus primario, se utilizar\u00e1 una herramienta dise\u00f1ada espec\u00edficamente para la exploraci\u00f3n de literatura para la infancia, denominada National Identity Analysis Tool (Sandis 2007), la que permitir\u00e1, en base a la constituci\u00f3n de una pre-codificaci\u00f3n probada, hacer un an\u00e1lisis enunciativo de elementos socioculturales diversos, as\u00ed como tambi\u00e9n narratol\u00f3gicos e intertextuales. El eje que permitir\u00e1 intervincular todos estos elementos ser\u00e1 la categor\u00eda \u0093geograf\u00eda y paisaje: dimensi\u00f3n espacial de las im\u00e1genes nacionales literarias\u0094 (Sandis 176). Para los procedimientos de registro del an\u00e1lisis textual\/gr\u00e1fico del corpus primario (fichaje), se dispondr\u00e1 del software de investigaci\u00f3n cualitativa en ciencias sociales y humanidades NVIVO, cuyas particularidades aportar\u00e1n altos niveles de sistematizaci\u00f3n y rigurosidad a los procesos anal\u00edticos que supone este proyecto.\r\nLos resultados esperados de este proyecto son, en primer lugar, contribuir a la exploraci\u00f3n y la expansi\u00f3n del conocimiento est\u00e9tico, pol\u00edtico e hist\u00f3rico de la literatura para las infancias en Chile, aportando a los debates historiogr\u00e1ficos, literarios y educacionales actuales en torno a las problem\u00e1ticas identitarias. En segundo lugar, como aportes materiales de esta investigaci\u00f3n se espera publicar al menos dos art\u00edculos indexados (Scopus y\/o WoS), realizar un seminario de alcance internacional, otro seminario de alcance nacional y consolidar una red investigativa internacional en torno a la l\u00ednea investigativa que propone el proyecto.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11230843<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2023 - Octubre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26430\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            &quot;Lo digo por tu salud&quot;: Sesgos, Estigma y Discriminaci\u00f3n por peso corporal experienciado por parte de mujeres en etapa de gestaci\u00f3n o puerperio\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26430\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26430\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Introducci\u00f3n: A lo largo del ciclo vital de las mujeres, pero especialmente durante la b\u00fasqueda de embarazo, la gestaci\u00f3n, o el puerperio, el peso corporal se vuelve un aspecto de especial relevancia en las interacciones entre usuarias y personal sanitario, por lo que las formas de abordar las variables asociadas a este pueden dejar huellas significativas en la mujer, tanto para su propia salud y bienestar, como para la de su descendencia. Las experiencias negativas asociadas al peso corporal, pueden tener consecuencias sobre la salud de las mujeres y de las generaciones venideras, tanto a nivel fisiol\u00f3gico como a nivel psicosocial. Pese a la relevancia de esta tem\u00e1tica, los sesgos, estigmas y discriminaci\u00f3n vivenciados por mujeres en etapa de gestaci\u00f3n y puerperio ha sido un fen\u00f3meno poco estudiado.\r\n\r\nObjetivos: Por lo anterior, los objetivos de esta propuesta son el analizar los sesgos, estigmas y discriminaci\u00f3n por peso corporal experienciados por mujeres en etapa de gestaci\u00f3n, puerperio o en edad f\u00e9rtil, y la relaci\u00f3n de estos factores con variables sociodemogr\u00e1ficas, asociadas al autocuidado, bienestar corporal y salud mental; observar si existen diferencias en relaci\u00f3n a los sesgos, estigmas y discriminaci\u00f3n por peso corporal en funci\u00f3n del momento del ciclo vital (gestaci\u00f3n, puerperio o mujeres en edad f\u00e9rtil) y caracterizar las experiencias de discriminaci\u00f3n por peso corporal, especialmente en contextos sanitarios, vivenciadas en los distintos momentos del ciclo vital (gestaci\u00f3n, puerperio o mujeres en edad f\u00e9rtil).\r\n\r\nMetodolog\u00eda: Para llevar a cabo lo anterior, se propone un estudio de tipo mixto, con un dise\u00f1o explicativo secuencial, conformado por tres etapas: una cuantitativa, una cualitativa y una fase de integraci\u00f3n de resultado. Se tratar\u00e1 de un estudio exploratorio, descriptivo, comparativo y de corte transversal. La captaci\u00f3n de participantes se realizar\u00e1 mediante un muestreo no probabil\u00edstico accidental para la etapa cuantitativa, y para la etapa cualitativa, se realizar\u00e1 un muestreo relacionado, ya que se extraer\u00e1 una submuestra a partir de la respuesta a uno de los instrumentos aplicados en la etapa cuantitativa. Se espera contar con participantes de sexo femenino, que residan en Chile, sean mayores de edad, tengan una edad entre 18 y 49 a\u00f1os, que sepan leer y escribir de modo aut\u00f3nomo y tengan acceso a internet. Se espera contar con tres grandes grupos de participantes: un primer grupo que se encuentre en etapa de gestaci\u00f3n, es decir, est\u00e9n cursando un embarazo, un segundo grupo que se encuentre en etapa de puerperio, es decir, se encuentren entre el d\u00eda 0 y 42 luego de haber parido, y un tercer grupo control, compuesto por mujeres en edad f\u00e9rtil, que no se encuentren ni en etapa de gestaci\u00f3n ni puerperio, que no hayan parido hace menos de 6 meses, ni pretendan hacerlo en los 6 meses posteriores a la aplicaci\u00f3n del instrumento. En la primera etapa del estudio se aplicar\u00e1 una bater\u00eda de cuestionarios en formato online, mediante los cuales se evaluar\u00e1n sesgos, estigmas y experiencias de discriminaci\u00f3n en funci\u00f3n del peso corporal, adem\u00e1s de variables sociodemogr\u00e1ficas, sintomatolog\u00eda asociada a cuadros de salud mental, y distintos indicadores asociados al autocuidado y bienestar corporal. En la segunda etapa se realizar\u00e1n entrevistas, en las cuales se espera contar con representaci\u00f3n de los tres grupos de participantes que hayan se\u00f1alado en la etapa anterior haber vivenciado experiencias discriminatorias en funci\u00f3n del peso corporal, a fin de poder profundizar en estas, poniendo especial \u00e9nfasis en aquellas producidas en entornos sanitarios. La \u00faltima etapa de la propuesta consistir\u00e1 en la integraci\u00f3n de la informaci\u00f3n recogida tanto a nivel cuantitativo como a nivel cualitativo.\r\n\r\nResultados Esperados: Se espera mediante esta propuesta, entre otras cosas, poder contar con conocimiento basado en la evidencia y pertinencia territorial acerca de la presencia de sesgos, estigma y comportamientos discriminatorios en funci\u00f3n del peso corporal, tanto en mujeres en etapas de gestaci\u00f3n y puerperio, como en mujeres en edad f\u00e9rtil en general, adem\u00e1s de conocer en detalle el tipo de experiencias vinculadas a las atenciones sanitarias que resultan m\u00e1s estigmatizantes para este grupo de la poblaci\u00f3n. A trav\u00e9s de lo anterior se espera poder contribuir al desarrollo de pol\u00edticas p\u00fablicas que permitan educar al personal sanitario, y a la poblaci\u00f3n general, sobre los efectos de este tipo de comportamientos tan socialmente masificados y aun aceptados a nivel poblacional, sobre la salud y el bienestar poblacional, pero especialmente en un momento del ciclo vital tan vulnerable al estr\u00e9s y al efecto que este pueda tener sobre las generaciones actuales y las venideras. Se espera poder desarrollar indicaciones de buenas pr\u00e1cticas no estigmatizantes, basadas en la evidencia, que en un futuro puedan formar parte de la formaci\u00f3n de personal sanitario y de campa\u00f1as comunicacionales masivas. Adem\u00e1s, se espera poder elaborar art\u00edculos cient\u00edficos, de modo de poder visibilizar la necesidad de seguir profundizando en este t\u00f3pico de investigaci\u00f3n. Por \u00faltimo, se busca iniciar a nivel nacional una l\u00ednea de investigaci\u00f3n que se espera contin\u00fae de modo prol\u00edfero m\u00e1s all\u00e1 de esta investigaci\u00f3n, continuando en un futuro con la incorporaci\u00f3n de marcadores biol\u00f3gicos, la evaluaci\u00f3n del personal sanitario involucrado y de la red social pr\u00f3xima, entre otros factores, a fin de enriquecer la comprensi\u00f3n multinivel del fen\u00f3meno.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2023 - Marzo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26559\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Interoceptive processing in auditory perception: a study to examine brain-body interactions.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26559\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26559\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The project aims to study the cardiac cycle's impact on brain responses and auditory perception. Using electroencephalogram and electrocardiogram recordings, we compare the neuronal responses to heartbeats in response to auditory stimulation in the different phases of the cardiac cycle. We evaluate interoceptive measures and traits of anxiety and depression in the population to establish relationships between neuronal activity and sensory and behavioral parameters.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11230719<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2023 - Marzo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26618\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fondecyt Iniciaci\u00f3n en la Investigaci\u00f3n: &#8220;Deposition and oxidation performance of hydrothermal alpha alumina coatings&#8221;\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26618\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26618\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Resumen[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11230505<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2023 - Marzo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26923\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            A Sensorization Toolbox for the Realization of Soft Physical Twins: Applications to Phantoms of Human Organs\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26923\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26923\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Desarrollo de r\u00e9plicas fidedignas e interactives de objetos deformables del mundo real. La principal aplicaci\u00f3n estudiada ser\u00e1n los phantomas de \u00f3rganos humanos, que permitir\u00e1n la validaci\u00f3n de intervenciones as\u00ed como ayudar durante la formaci\u00f3n de especialistas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> Fondecyt de Iniciaci\u00f3n 11230184<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2023 - Marzo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26318\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fondecyt de Iniciaci\u00f3n 11230184 Atmospheric water vapor and precipitation processes in central and southern Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26318\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26318\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Water vapor is a key component of the hydrological cycle since it is directly involved in the production of precipitation (rain, snow, hail). The transport of water vapor from the tropics (20\u00baN-20\u00baS) is fundamental to produce precipitation in midlatitudes (30\u00baS-50\u00baS) were local amounts atmospheric moisture are lower than the water column precipitated during a typical storm. This is especially evident during extreme precipitation events, where precipitation accumulation can surpass 2 or 3 times the local atmospheric water vapor available.\r\nExtreme precipitation events (EPEs) are expected to increase due to the anthropogenic climate change, and therefore studies addressing the dynamics and forcing factors of these events are increasingly important. Current research examining the relationship between water vapor transport and precipitation in central-southern Chile have advanced in this direction. However, there is a lack of research aiming to understand water-vapor-precipitation process at the mesoscale, where changes in the order of hours associated to convection are important. Even more, despite many storms in central-southern Chile show convective characteristics (e.g. precipitation rates of 10 mm\/h or larger), studies looking at the mesoscale processes has not been addressed so far, partially due to the lack of ground-based weather radars.\r\nAs a result, this research proposal takes the challenge of studying the transport of water vapor and link it with precipitation processes (stratiform and convective) at the mesoscale level in central and southern Chile by using a suit of observations and numerical modeling. To determine the water vapor mechanisms involved in the precipitation processes, the study will employ an atmospheric moisture budget, which involves the balance between a storage term (precipitation in this case) and the linear interaction between local changes, advection, and convergence of water vapor following an air parcel. The budget will be computed using gridded data from a state-of-the-art atmospheric reanalysis (ERA5), numerical simulations with the Weather Research and Forecasting (WRF) model, and mathematical techniques such as finite differences and the trapezoidal integration rule. In addition, a relatively dense network of GPS deployed in central-southern Chile will provide direct estimates of local changes of the column water vapor, allowing us to perform a thorough validation of both ERA5 and WRF. \r\nPrecipitation processes will be examined using several sources. The polar orbiting Global Precipitation Measurement (GPM) satellite mission provides global swaths of radar reflectivity using a dual-frequency radar (Ku and Ka bands) in a swath-width of 245 km with 5 km resolution at nadir, and vertical beams spaced at 250 m. Along with radar reflectivity, GPM provides estimates of precipitation rates and a classification of the precipitation type, facilitating the identification of precipitation processes. A vertically pointing precipitation radar (Micro Rain Radar, MRR) is currently installed at Universidad de Concepci\u00f3n and will provide time-height sections of radar reflectivity that will complement GPM observations. In addition, a second MRR is planned to be installed in central Chile to provide further meridional context of precipitation processes. Finally, a couple of optical disdrometers and meteorological stations will deliver surface estimates of precipitation at hourly (and higher) rates. In parallel, ERA5 will provide precipitation estimations and classification (stratiform, convective), while WRF will allow to examine precipitation in detail for selected case studies.\r\nAt the end of this project, it will be clear what component(s) of the moisture budget are dominating precipitation during EPE storms, clarify the relative importance of stratiform and convective precipitation during EPEs, and elucidate if EPEs with strong convective precipitation are forced by atmospheric instabilities, advection of moisture being lifted by the complex terrain, or moisture convergence occurring over the ocean and moving inland. These results will provide the basis for future efforts looking to improve precipitation forecasting tools.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26984\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Legitimidad de las polic\u00edas en Chile: el efecto causal de la violencia y la corrupci\u00f3n desde una perspectiva multi-actor, longitudinal y multi-me&#769;todos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26984\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26984\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Materia Espec\u00edfica: El proyecto busca generar informaci\u00f3n sobre los niveles de legitimidad y justicia procedimental de las polic\u00edas entre la ciudadan\u00eda de Chile durante los pr\u00f3ximos 3 a\u00f1os, as\u00ed como entender los antecedentes que pueden llevar a un aumento o disminuci\u00f3n de las mismas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26053\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia huevos con calidad integral certificada\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26053\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26053\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La producci\u00f3n de huevos es una actividad com\u00fan en explotaciones de tama\u00f1o peque\u00f1o y mediano, siendo habitual su complementariedad con otras actividades agropecuarias. El huevo como alimento posee un alto valor nutricional, en t\u00e9rminos de amino\u00e1cidos esenciales (alto valor biol\u00f3gico), vitaminas (A, D, B12, riboflavina, niacina), minerales (f\u00f3sforo, yodo y selenio) y \u00e1cidos grasos monoinsaturados. La producci\u00f3n de huevos en Chile est\u00e1 en mano de alrededor de 300 productores de los cuales 57 aportan con m\u00e1s del 90% de la producci\u00f3n. Estos grandes productores generalmente usan sistemas intensivos de producci\u00f3n que no favorecen el comportamiento natural de las aves (caminar, escarbar, perchar, aletear, tomar ba\u00f1os de tierra, etc.) y junto con ello, dado su tama\u00f1o y las altas densidades de aves manejadas producen externalidades negativas que incluyen la generaci\u00f3n de olores, ruidos, aumento de la presencia de plagas y generaci\u00f3n de altos vol\u00famenes de desechos org\u00e1nicos (guano y animales muertos). Los peque\u00f1os productores av\u00edcolas, donde destaca un alto porcentaje de mujeres dedicadas a la actividad, al manejar un menor n\u00famero de animales, utilizan sistemas de producci\u00f3n m\u00e1s naturales, donde las aves son criadas libres de jaula conviviendo de manera arm\u00f3nica con el ambiente, utilizando sus recursos de forma sostenible, y generando e integrando desechos de manera racional. No obstante, estos sistemas de producci\u00f3n al encontrarse en sectores rurales presentan brechas de comercializaci\u00f3n, as\u00ed como falta de acceso a lugares de compra de insumos y falta de capacitaciones para la mejora de sus sistemas. Sumado a esto, este tipo de producci\u00f3n amigable, con el medio ambiente y con las aves, genera productos de mayor calidad nutricional y organol\u00e9ptica, caracter\u00edsticas que, si bien son valoradas por los consumidores, no cuentan con un sistema de certificaci\u00f3n que las respalde y asegure su estabilidad temporal y por lo tanto permita una mayor valoraci\u00f3n econ\u00f3mica del producto. Por otro lado, la producci\u00f3n de huevos en peque\u00f1os y medianos propietarios presenta una amplia diversidad en cuanto a infraestructura, n\u00famero de aves, sistema de producci\u00f3n, alimentaci\u00f3n e importancia de la actividad dentro de la explotaci\u00f3n. \r\nConsiderando lo planteado anteriormente el objetivo general del proyecto es la generaci\u00f3n y validaci\u00f3n de un sistema de producci\u00f3n de huevos free range con calidad integral certificada. Para lograr este objetivo general la propuesta contempla los siguientes objetivos espec\u00edficos:\r\n-\tCaracterizaci\u00f3n de los productores, an\u00e1lisis de mercado e identificaci\u00f3n de brechas\r\n-\tValidaci\u00f3n de prototipos de producci\u00f3n de ponedoras free range bajo pastoreo tradicional y regenerativo\r\n-\tDesarrollo de un modelo de certificaci\u00f3n de calidad nutricional del huevo basado en la tecnolog\u00eda NIRS (Near Infrared Spectroscopy)\r\n-\tElaboraci\u00f3n y validaci\u00f3n de dietas para ponedoras basadas en productos y subproductos locales con evaluaci\u00f3n de su inocuidad \r\n-\tEvaluaci\u00f3n de la huella de carbono de los sistemas de producci\u00f3n actuales y propuestos \r\n-\tArticulaci\u00f3n y encadenamiento productivo-comercial a trav\u00e9s de capacitaci\u00f3n, difusi\u00f3n y desarrollo de redes de comercializaci\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2023 - Febrero 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26276\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fabricaci\u00f3n digital para J\u00f3venes Makers\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26276\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26276\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La fabricaci\u00f3n digital es un concepto que est\u00e1 revolucionando el modo en que se producen piezas y objetos. Hace referencia a procesos de manufactura en los que se usan m\u00e1quinas controladas por una computadora para fabricar un objeto, previamente dise\u00f1ado en alg\u00fan software. La fabricaci\u00f3n digital incluye tecnolog\u00edas como impresi\u00f3n y escaneo 3D, corte l\u00e1ser y mecanizado CNC (control num\u00e9rico computarizado); que junto al dise\u00f1o CAD (dise\u00f1o asistido por computadora) y programaci\u00f3n permiten procesar archivos digitales para construir objetos tangibles. Tambi\u00e9n se relaciona con el modelo educativo STEAM (ciencia, tecnolog\u00eda, ingenier\u00eda, arte y matem\u00e1tica) y con tecnolog\u00edas que definen la pr\u00f3xima revoluci\u00f3n industrial, la industria 4.0.\r\nLa fabricaci\u00f3n digital puede ser considerada un medio para desarrollar competencias como la creatividad, la colaboraci\u00f3n y el trabajo en equipo, la proactividad y el emprendimiento. Numerosas experiencias internacionales y nacionales en fabricaci\u00f3n digital han demostrado ser eficaces en fomentar competencias transversales en estudiantes, a diferencia del simple uso de dispositivos electr\u00f3nicos (por ejemplo, smartphones). La eficacia de la fabricaci\u00f3n digital radica en que, si bien tambi\u00e9n implica el uso de dispositivos electr\u00f3nicos, pone el foco en conceptualizar, desarrollar y construir un producto f\u00edsico. En consecuencia, esta nueva filosof\u00eda basada en el \u0093aprender haciendo\u0094 aumenta la motivaci\u00f3n, otorga autonom\u00eda y brinda competencias laborales fundamentales para el siglo XXI.\r\nLa pandemia Covid-19 ha tra\u00eddo p\u00e9rdidas irreparables, pero tambi\u00e9n grandes aprendizajes y desaf\u00edos tecnol\u00f3gicos. Se ha acelerado la transformaci\u00f3n digital y se ha manifestado un gran potencial de desarrollo tecnol\u00f3gico local. Por otra parte, tambi\u00e9n se han visualizado brechas digitales y de g\u00e9nero en la educaci\u00f3n chilena. Desde el punto de vista del impacto en aprendizaje en contexto de pandemia, se ha determinado que la Regi\u00f3n de O\u0092Higgins podr\u00eda ser una de las m\u00e1s perjudicadas por el cierre prolongado de los establecimientos educacionales (MINEDUC, 2020). Sumado a ello, es particularmente preocupante la diferencia, en detrimento de las ni\u00f1as y las adolescentes, que ocurre con el desempe\u00f1o en \u00e1reas STEAM, por lo crucial que estas resultan en las futuras oportunidades, nivel de ingresos y calidad de vida a la que podr\u00e1n acceder (UNESCO, 2019).\r\nLa Estrategia Regional de Innovaci\u00f3n identifica la baja formaci\u00f3n e incorporaci\u00f3n de nuevas tecnolog\u00edas 4.0 como una brecha que limita la puesta en marcha de proyectos innovadores y la asociatividad entre los actores regionales. Indicadores comunes para medir la efectividad de la innovaci\u00f3n empresarial y emprendimiento tecnol\u00f3gico son instrumentos de propiedad industrial, como patentes, y surgimiento de empresas de base tecnol\u00f3gica. Las estad\u00edsticas de la Regi\u00f3n de O\u0092Higgins no son buenas. Seg\u00fan los \u00faltimos datos de INAPI, apenas el 1,33% de las patentes solicitadas en Chile provienen de la Regi\u00f3n de O\u0092Higgins. Por otro lado, no existen registros de emprendimientos regionales de base tecnol\u00f3gica.\r\nLa incorporaci\u00f3n de las tecnolog\u00edas de fabricaci\u00f3n digital en la formaci\u00f3n de j\u00f3venes makers puede fortalecer la educaci\u00f3n STEAM, reducir la brecha digital y de g\u00e9nero y potenciar los procesos de innovaci\u00f3n empresarial y emprendimiento tecnol\u00f3gico en la Regi\u00f3n de O\u0092Higgins.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FONDECYT Regular no. 1230457<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2023 - Febrero 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26374\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Rats and zoonotic pathogens: identifying environmental factors of infestation and infection along anthropogenic gradients in Central Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26374\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26374\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Anthropogenic land use change is a major driver of transmission and emergence of zoonotic diseases in\r\nhumans. Land use change can also favor invasive species such as rats (Rattus norvegicus and R. rattus).\r\nThese rats are known as reservoir of zoonotic pathogens and have invaded a vast number of regions in the\r\nworld, impacting biodiversity, economy, and human health. Both rat species have colonized a wide range\r\nof natural areas in Chile, particularly in the Mediterranean region of Central Chile, which is a highly\r\nvulnerable region that has suffered profound land use transformation. Despite this, ecological and\r\nepidemiological studies on invasive rats in the Mediterranean central Chile are scarce. In this project, we\r\nwill assess Rattus spp. infestation (presence and abundance of rats) and pathogen infection along\r\nanthropogenic gradients (periurban-rural-natural gradients) in central Chile, with the aim to understand\r\nwhat environmental factors are associated with rat infestation and pathogen infections in different land use\r\nand landscapes. Furthermore, we will forecast and map the presence of Rattus spp. under future land use\r\nscenarios in central Chile.\r\nA complete understanding of the distribution and abundance of hosts and pathogens and their relationship\r\nwith the environment requires studies to be conducted at multiple spatial scales. Therefore, in this project,\r\nwe will use a multi-scale spatial approach to address environmental drivers of rat infestation and pathogen\r\ninfection. These gradients will allow us to assess the dynamic of pathogens at transition zones between\r\ndifferent land use, which is considered a research priority in the study of infectious pathogens in wildlife.\r\nAmong a variety of pathogens associated with rats, in this project we will focus in three different\r\npathogens: Bartonella spp., Leptospira spp., and Trypanosoma cruzi. These pathogens are of public health\r\nconcern and represent different types of pathogens (bacteria and protozoa), with different mode of\r\ntransmissions. These different characteristics may cause these pathogens to respond in different ways to\r\ntransformation of land.\r\nThe study will be conducted at 45 sites located in five large areas within three administrative regions\r\n(Valpara\u00edso Region, Metropolitan Region, and the O'Higgins Region). We will examinate the influence of\r\nenvironmental factors on rat infestation and pathogen infection at three spatial scales: microhabitat scale\r\n(at the point where traps are located), patch or local scale (the sampling site), and landscape scale (i.e.,\r\nbuffer zone surrounding sampling sites). To assess rat presence and abundance, we will use passive\r\nmethods (camera trapping, tracking tunnels) and active methods (live trapping). For pathogen infection,\r\nwe will conduct molecular analyses for all three pathogens. Finally, to model and forecast the presence and\r\ndistribution of rats at regional scale, we will use classification tree analysis on the presence of both rat\r\nspecies to produce hierarchical models that describe the relationships between presence of rats and land\r\nuse variables. Data to conduct these models will be retrieved from our own data collected in this project\r\nalong with other data of Rattus spp. occurrence in central Chile obtained from different repositories. We\r\nwill use future land use scenarios for 2050 and 2080 available in the Land-Use Harmonization project.\r\nWe expect to find that the main variables determining rat infestation and pathogen infection across\r\ngradients will be the anthropogenic features existing in different habitats and occurring at different spatial\r\nscales. We also expect that populations of both Rattus species will increase their presence and distribution\r\nin the Mediterranean region under future land use scenarios of greater urban and rural expansion.\r\nEffectively strategies of managing zoonotic risks from wild animal hosts requires an understanding of how\r\nlandscape patterns influence populations of hosts and their associated pathogens. Therefore, the results of\r\n\r\n2023 Regular Fondecyt National Projects Competition\r\nthis project can be useful for potential management of invasive rats and for strategies to prevent zoonotic\r\npathogen risk.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 22993<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26459\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Red Compromiso con el desarrollo sustentable\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26459\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26459\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto en red que agrupa a universidades del consorcio del estado para fomentar el desarrollo sostenible en las instituciones de educaci\u00f3n desde la gesti\u00f3n y diferentes practicas.  Mi rol en el proyecto es de coordinador institucional y participo en el OE2[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2023 - Diciembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26620\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia: c\u00e1mara de simulaci\u00f3n agroclim\u00e1tica\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26620\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26620\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La agricultura es una de las principales actividades econ\u00f3micas de la Regi\u00f3n de O\u0092Higgins, con un PIB que alcanza al a\u00f1o 2021 el 12,8% de representaci\u00f3n a nivel nacional. El \u00e9xito productivo regional\r\ndepende en gran medida de las condiciones edafoclim\u00e1ticas que preponderan en las zonas cultivables y\/o aptas para la agricultura. Sin embargo, el actual escenario de cambio clim\u00e1tico genera\r\nuna alteraci\u00f3n de estas variables clim\u00e1ticas, con cambios evidentes en la variabilidad de las precipitaciones, frecuencia e intensidad de los d\u00edas c\u00e1lidos y fr\u00edos, y eventos clim\u00e1ticos extremos\r\n(heladas, granizo, entre otros). Consecuentemente, el impacto del cambio clim\u00e1tico ha modificado y seguir\u00e1 transformando los sistemas de producci\u00f3n de diversos cultivos a nivel nacional y local,\r\nincluyendo el cambio de las zonas productivas. \r\nEsta nueva realidad clim\u00e1tica requiere de la pronta generaci\u00f3n de conocimiento y la capacidad de innovar y desarrollar tecnolog\u00edas inteligentes para adaptar y asegurar la producci\u00f3n de alimentos.\r\nAunque existe conocimiento de los posibles efectos del cambio clim\u00e1tico sobre la agricultura, la literatura indica que la diversidad geogr\u00e1fica y clim\u00e1tica de la producci\u00f3n agr\u00edcola no permite predecir\r\ncon precisi\u00f3n los impactos locales del cambio clim\u00e1tico en los diferentes cultivos. Por lo tanto, la mejor forma de reducir esta incertidumbre clim\u00e1tica es a trav\u00e9s del desarrollo de tecnolog\u00eda, el\r\nconocimiento y la innovaci\u00f3n aplicada para adaptar y asegurar la producci\u00f3n de alimentos. De hecho, la Conferencia de las Partes de la Convenci\u00f3n de Cambio Clim\u00e1tico realizada en Par\u00eds (COP21),\r\nenfatiza la necesidad de avanzar hacia una \u0093agricultura clim\u00e1ticamente inteligente\u0094, es decir, una actividad que entre en sinton\u00eda con los cambios globales, con m\u00ednima huella ambiental, altamente\r\neficiente en el uso de insumos, resiliente, productiva y sostenible. \r\nEste proyecto plantea la construcci\u00f3n de infraestructura clim\u00e1ticamente inteligente como la primera c\u00e1mara de simulaci\u00f3n clim\u00e1tica regional, la cual permitir\u00e1 determinar el impacto de diferentes\r\nescenarios de cambio clim\u00e1tico en cultivos y variedades de importancia para los agricultores de la Regi\u00f3n de O\u0092Higgins de manera anticipada. Se busca responder las interrogantes asociadas a qu\u00e9\r\ncultivos son m\u00e1s id\u00f3neos para las distintas zonas geogr\u00e1ficas de la Regi\u00f3n de O\u0092Higgins, bajo condiciones extremas de temperatura, humedad ambiental y disponibilidad de agua, entre otros\r\naspectos. Con la informaci\u00f3n generada se desarrollar\u00e1n directrices tecnol\u00f3gicas y sistemas de bajo costo para la medici\u00f3n de par\u00e1metros ambientales, con el fin de brindar a los agricultores soporte \r\npara la toma de decisiones a nivel local, y consecuentemente fortalecer la competitividad del sector agr\u00edcola de la Regi\u00f3n de O\u0092Higgins.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2023 - Diciembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26635\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia: c\u00e1mara de simulaci\u00f3n agroclim\u00e1tica\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26635\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26635\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La agricultura es una de las principales actividades econ\u00f3micas de la Regi\u00f3n de O\u0092Higgins, con un PIB que alcanza al a\u00f1o 2021 el 12,8% de representaci\u00f3n a nivel nacional. El \u00e9xito productivo regional\r\ndepende en gran medida de las condiciones edafoclim\u00e1ticas que preponderan en las zonas cultivables y\/o aptas para la agricultura. Sin embargo, el actual escenario de cambio clim\u00e1tico genera\r\nuna alteraci\u00f3n de estas variables clim\u00e1ticas, con cambios evidentes en la variabilidad de las precipitaciones, frecuencia e intensidad de los d\u00edas c\u00e1lidos y fr\u00edos, y eventos clim\u00e1ticos extremos\r\n(heladas, granizo, entre otros). Consecuentemente, el impacto del cambio clim\u00e1tico ha modificado y seguir\u00e1 transformando los sistemas de producci\u00f3n de diversos cultivos a nivel nacional y local,\r\nincluyendo el cambio de las zonas productivas. \r\nEsta nueva realidad clim\u00e1tica requiere de la pronta generaci\u00f3n de conocimiento y la capacidad de innovar y desarrollar tecnolog\u00edas inteligentes para adaptar y asegurar la producci\u00f3n de alimentos.\r\nAunque existe conocimiento de los posibles efectos del cambio clim\u00e1tico sobre la agricultura, la literatura indica que la diversidad geogr\u00e1fica y clim\u00e1tica de la producci\u00f3n agr\u00edcola no permite predecir\r\ncon precisi\u00f3n los impactos locales del cambio clim\u00e1tico en los diferentes cultivos. Por lo tanto, la mejor forma de reducir esta incertidumbre clim\u00e1tica es a trav\u00e9s del desarrollo de tecnolog\u00eda, el\r\nconocimiento y la innovaci\u00f3n aplicada para adaptar y asegurar la producci\u00f3n de alimentos. De hecho, la Conferencia de las Partes de la Convenci\u00f3n de Cambio Clim\u00e1tico realizada en Par\u00eds (COP21),\r\nenfatiza la necesidad de avanzar hacia una \u0093agricultura clim\u00e1ticamente inteligente\u0094, es decir, una actividad que entre en sinton\u00eda con los cambios globales, con m\u00ednima huella ambiental, altamente\r\neficiente en el uso de insumos, resiliente, productiva y sostenible. \r\nEste proyecto plantea la construcci\u00f3n de infraestructura clim\u00e1ticamente inteligente como la primera c\u00e1mara de simulaci\u00f3n clim\u00e1tica regional, la cual permitir\u00e1 determinar el impacto de diferentes\r\nescenarios de cambio clim\u00e1tico en cultivos y variedades de importancia para los agricultores de la Regi\u00f3n de O\u0092Higgins de manera anticipada. Se busca responder las interrogantes asociadas a qu\u00e9\r\ncultivos son m\u00e1s id\u00f3neos para las distintas zonas geogr\u00e1ficas de la Regi\u00f3n de O\u0092Higgins, bajo condiciones extremas de temperatura, humedad ambiental y disponibilidad de agua, entre otros\r\naspectos. Con la informaci\u00f3n generada se desarrollar\u00e1n directrices tecnol\u00f3gicas y sistemas de bajo costo para la medici\u00f3n de par\u00e1metros ambientales, con el fin de brindar a los agricultores soporte \r\npara la toma de decisiones a nivel local, y consecuentemente fortalecer la competitividad del sector agr\u00edcola de la Regi\u00f3n de O\u0092Higgins.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2023 - Febrero 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26641\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fabricaci\u00f3n digital para J\u00f3venes Makers\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26641\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26641\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La fabricaci\u00f3n digital es un concepto que est\u00e1 revolucionando el modo en que se producen piezas y objetos. Hace referencia a procesos de manufactura en los que se usan m\u00e1quinas controladas por una computadora para fabricar un objeto, previamente dise\u00f1ado en alg\u00fan software. La fabricaci\u00f3n digital incluye tecnolog\u00edas como impresi\u00f3n y escaneo 3D, corte l\u00e1ser y mecanizado CNC (control num\u00e9rico computarizado); que junto al dise\u00f1o CAD (dise\u00f1o asistido por computadora) y programaci\u00f3n permiten procesar archivos digitales para construir objetos tangibles. Tambi\u00e9n se relaciona con el modelo educativo STEAM (ciencia, tecnolog\u00eda, ingenier\u00eda, arte y matem\u00e1tica) y con tecnolog\u00edas que definen la pr\u00f3xima revoluci\u00f3n industrial, la industria 4.0.\r\nLa fabricaci\u00f3n digital puede ser considerada un medio para desarrollar competencias como la creatividad, la colaboraci\u00f3n y el trabajo en equipo, la proactividad y el emprendimiento. Numerosas experiencias internacionales y nacionales en fabricaci\u00f3n digital han demostrado ser eficaces en fomentar competencias transversales en estudiantes, a diferencia del simple uso de dispositivos electr\u00f3nicos (por ejemplo, smartphones). La eficacia de la fabricaci\u00f3n digital radica en que, si bien tambi\u00e9n implica el uso de dispositivos electr\u00f3nicos, pone el foco en conceptualizar, desarrollar y construir un producto f\u00edsico. En consecuencia, esta nueva filosof\u00eda basada en el \u0093aprender haciendo\u0094 aumenta la motivaci\u00f3n, otorga autonom\u00eda y brinda competencias laborales fundamentales para el siglo XXI.\r\nLa pandemia Covid-19 ha tra\u00eddo p\u00e9rdidas irreparables, pero tambi\u00e9n grandes aprendizajes y desaf\u00edos tecnol\u00f3gicos. Se ha acelerado la transformaci\u00f3n digital y se ha manifestado un gran potencial de desarrollo tecnol\u00f3gico local. Por otra parte, tambi\u00e9n se han visualizado brechas digitales y de g\u00e9nero en la educaci\u00f3n chilena. Desde el punto de vista del impacto en aprendizaje en contexto de pandemia, se ha determinado que la Regi\u00f3n de O\u0092Higgins podr\u00eda ser una de las m\u00e1s perjudicadas por el cierre prolongado de los establecimientos educacionales (MINEDUC, 2020). Sumado a ello, es particularmente preocupante la diferencia, en detrimento de las ni\u00f1as y las adolescentes, que ocurre con el desempe\u00f1o en \u00e1reas STEAM, por lo crucial que estas resultan en las futuras oportunidades, nivel de ingresos y calidad de vida a la que podr\u00e1n acceder (UNESCO, 2019).\r\nLa Estrategia Regional de Innovaci\u00f3n identifica la baja formaci\u00f3n e incorporaci\u00f3n de nuevas tecnolog\u00edas 4.0 como una brecha que limita la puesta en marcha de proyectos innovadores y la asociatividad entre los actores regionales. Indicadores comunes para medir la efectividad de la innovaci\u00f3n empresarial y emprendimiento tecnol\u00f3gico son instrumentos de propiedad industrial, como patentes, y surgimiento de empresas de base tecnol\u00f3gica. Las estad\u00edsticas de la Regi\u00f3n de O\u0092Higgins no son buenas. Seg\u00fan los \u00faltimos datos de INAPI, apenas el 1,33% de las patentes solicitadas en Chile provienen de la Regi\u00f3n de O\u0092Higgins. Por otro lado, no existen registros de emprendimientos regionales de base tecnol\u00f3gica.\r\nLa incorporaci\u00f3n de las tecnolog\u00edas de fabricaci\u00f3n digital en la formaci\u00f3n de j\u00f3venes makers puede fortalecer la educaci\u00f3n STEAM, reducir la brecha digital y de g\u00e9nero y potenciar los procesos de innovaci\u00f3n empresarial y emprendimiento tecnol\u00f3gico en la Regi\u00f3n de O\u0092Higgins.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2023 - Diciembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26872\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia: c\u00e1mara de simulaci\u00f3n agroclim\u00e1tica\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26872\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26872\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La agricultura es una de las principales actividades econ\u00f3micas de la Regi\u00f3n de O\u0092Higgins, con un PIB que alcanza al a\u00f1o 2021 el 12,8% de representaci\u00f3n a nivel nacional. El \u00e9xito productivo regional\r\ndepende en gran medida de las condiciones edafoclim\u00e1ticas que preponderan en las zonas cultivables y\/o aptas para la agricultura. Sin embargo, el actual escenario de cambio clim\u00e1tico genera\r\nuna alteraci\u00f3n de estas variables clim\u00e1ticas, con cambios evidentes en la variabilidad de las precipitaciones, frecuencia e intensidad de los d\u00edas c\u00e1lidos y fr\u00edos, y eventos clim\u00e1ticos extremos\r\n(heladas, granizo, entre otros). Consecuentemente, el impacto del cambio clim\u00e1tico ha modificado y seguir\u00e1 transformando los sistemas de producci\u00f3n de diversos cultivos a nivel nacional y local,\r\nincluyendo el cambio de las zonas productivas. \r\nEsta nueva realidad clim\u00e1tica requiere de la pronta generaci\u00f3n de conocimiento y la capacidad de innovar y desarrollar tecnolog\u00edas inteligentes para adaptar y asegurar la producci\u00f3n de alimentos.\r\nAunque existe conocimiento de los posibles efectos del cambio clim\u00e1tico sobre la agricultura, la literatura indica que la diversidad geogr\u00e1fica y clim\u00e1tica de la producci\u00f3n agr\u00edcola no permite predecir\r\ncon precisi\u00f3n los impactos locales del cambio clim\u00e1tico en los diferentes cultivos. Por lo tanto, la mejor forma de reducir esta incertidumbre clim\u00e1tica es a trav\u00e9s del desarrollo de tecnolog\u00eda, el\r\nconocimiento y la innovaci\u00f3n aplicada para adaptar y asegurar la producci\u00f3n de alimentos. De hecho, la Conferencia de las Partes de la Convenci\u00f3n de Cambio Clim\u00e1tico realizada en Par\u00eds (COP21),\r\nenfatiza la necesidad de avanzar hacia una \u0093agricultura clim\u00e1ticamente inteligente\u0094, es decir, una actividad que entre en sinton\u00eda con los cambios globales, con m\u00ednima huella ambiental, altamente\r\neficiente en el uso de insumos, resiliente, productiva y sostenible. \r\nEste proyecto plantea la construcci\u00f3n de infraestructura clim\u00e1ticamente inteligente como la primera c\u00e1mara de simulaci\u00f3n clim\u00e1tica regional, la cual permitir\u00e1 determinar el impacto de diferentes\r\nescenarios de cambio clim\u00e1tico en cultivos y variedades de importancia para los agricultores de la Regi\u00f3n de O\u0092Higgins de manera anticipada. Se busca responder las interrogantes asociadas a qu\u00e9\r\ncultivos son m\u00e1s id\u00f3neos para las distintas zonas geogr\u00e1ficas de la Regi\u00f3n de O\u0092Higgins, bajo condiciones extremas de temperatura, humedad ambiental y disponibilidad de agua, entre otros\r\naspectos. Con la informaci\u00f3n generada se desarrollar\u00e1n directrices tecnol\u00f3gicas y sistemas de bajo costo para la medici\u00f3n de par\u00e1metros ambientales, con el fin de brindar a los agricultores soporte \r\npara la toma de decisiones a nivel local, y consecuentemente fortalecer la competitividad del sector agr\u00edcola de la Regi\u00f3n de O\u0092Higgins.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2023 - Febrero 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26877\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fabricaci\u00f3n digital para J\u00f3venes Makers\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26877\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26877\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La fabricaci\u00f3n digital es un concepto que est\u00e1 revolucionando el modo en que se producen piezas y objetos. Hace referencia a procesos de manufactura en los que se usan m\u00e1quinas controladas por una computadora para fabricar un objeto, previamente dise\u00f1ado en alg\u00fan software. La fabricaci\u00f3n digital incluye tecnolog\u00edas como impresi\u00f3n y escaneo 3D, corte l\u00e1ser y mecanizado CNC (control num\u00e9rico computarizado); que junto al dise\u00f1o CAD (dise\u00f1o asistido por computadora) y programaci\u00f3n permiten procesar archivos digitales para construir objetos tangibles. Tambi\u00e9n se relaciona con el modelo educativo STEAM (ciencia, tecnolog\u00eda, ingenier\u00eda, arte y matem\u00e1tica) y con tecnolog\u00edas que definen la pr\u00f3xima revoluci\u00f3n industrial, la industria 4.0.\r\nLa fabricaci\u00f3n digital puede ser considerada un medio para desarrollar competencias como la creatividad, la colaboraci\u00f3n y el trabajo en equipo, la proactividad y el emprendimiento. Numerosas experiencias internacionales y nacionales en fabricaci\u00f3n digital han demostrado ser eficaces en fomentar competencias transversales en estudiantes, a diferencia del simple uso de dispositivos electr\u00f3nicos (por ejemplo, smartphones). La eficacia de la fabricaci\u00f3n digital radica en que, si bien tambi\u00e9n implica el uso de dispositivos electr\u00f3nicos, pone el foco en conceptualizar, desarrollar y construir un producto f\u00edsico. En consecuencia, esta nueva filosof\u00eda basada en el \u0093aprender haciendo\u0094 aumenta la motivaci\u00f3n, otorga autonom\u00eda y brinda competencias laborales fundamentales para el siglo XXI.\r\nLa pandemia Covid-19 ha tra\u00eddo p\u00e9rdidas irreparables, pero tambi\u00e9n grandes aprendizajes y desaf\u00edos tecnol\u00f3gicos. Se ha acelerado la transformaci\u00f3n digital y se ha manifestado un gran potencial de desarrollo tecnol\u00f3gico local. Por otra parte, tambi\u00e9n se han visualizado brechas digitales y de g\u00e9nero en la educaci\u00f3n chilena. Desde el punto de vista del impacto en aprendizaje en contexto de pandemia, se ha determinado que la Regi\u00f3n de O\u0092Higgins podr\u00eda ser una de las m\u00e1s perjudicadas por el cierre prolongado de los establecimientos educacionales (MINEDUC, 2020). Sumado a ello, es particularmente preocupante la diferencia, en detrimento de las ni\u00f1as y las adolescentes, que ocurre con el desempe\u00f1o en \u00e1reas STEAM, por lo crucial que estas resultan en las futuras oportunidades, nivel de ingresos y calidad de vida a la que podr\u00e1n acceder (UNESCO, 2019).\r\nLa Estrategia Regional de Innovaci\u00f3n identifica la baja formaci\u00f3n e incorporaci\u00f3n de nuevas tecnolog\u00edas 4.0 como una brecha que limita la puesta en marcha de proyectos innovadores y la asociatividad entre los actores regionales. Indicadores comunes para medir la efectividad de la innovaci\u00f3n empresarial y emprendimiento tecnol\u00f3gico son instrumentos de propiedad industrial, como patentes, y surgimiento de empresas de base tecnol\u00f3gica. Las estad\u00edsticas de la Regi\u00f3n de O\u0092Higgins no son buenas. Seg\u00fan los \u00faltimos datos de INAPI, apenas el 1,33% de las patentes solicitadas en Chile provienen de la Regi\u00f3n de O\u0092Higgins. Por otro lado, no existen registros de emprendimientos regionales de base tecnol\u00f3gica.\r\nLa incorporaci\u00f3n de las tecnolog\u00edas de fabricaci\u00f3n digital en la formaci\u00f3n de j\u00f3venes makers puede fortalecer la educaci\u00f3n STEAM, reducir la brecha digital y de g\u00e9nero y potenciar los procesos de innovaci\u00f3n empresarial y emprendimiento tecnol\u00f3gico en la Regi\u00f3n de O\u0092Higgins.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Sigma Xi Grants in Aid of Research<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27067\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Experimental Ge\/Si partitioning as a fossilization tracer of Earth\u0092s earliest animal ecosystems\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27067\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27067\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The goal of this project was to test the Ge\/Si proxy in silicification processes[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2023 - Marzo 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>SOCHINUT-NESTLE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27082\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            La suplementaci\u00f3n diaria con cuerpos cet\u00f3nicos durante la recuperaci\u00f3n de una lesi\u00f3n aguda previene la infiltraci\u00f3n grasa y acelera la reparaci\u00f3n muscular\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27082\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27082\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La respuesta inflamatoria al da\u00f1o muscular puede comprometer la fuerza\/masa al inducir la formaci\u00f3n de\r\ntejido adiposo intermuscular (IMAT). IMAT se origina de la diferenciaci\u00f3n adipog\u00e9nica de c\u00e9lulas\r\nmesenquimales progenitoras fibro-adipog\u00e9nicas (FAPs). Este proceso podr\u00eda revertirse modulando la\r\nrespuesta inflamatoria aguda. Sin embargo, el uso de antiinflamatorios inhibe la s\u00edntesis proteica y reduce\r\nla capacidad regenerativa muscular. Alternativamente, medidas f\u00edsicas como el reposo funcional o la\r\nreincorporaci\u00f3n temprana a la actividad han reportado efectos contradictorios sobre el proceso\r\ninflamatorio, lo que dificulta establecer indicaciones en el manejo de la lesi\u00f3n muscular. Por otro lado, se\r\nha descrito un potente papel antinflamatorio local o sist\u00e9mico del cuerpo cet\u00f3nico &#946;-hydroxybutirato\r\n(&#946;HB); efecto mediado por la inhibici\u00f3n del inflamasoma NLRP3 y la secreci\u00f3n de citoquinas\r\nproinflamatorias. Importantemente, la activaci\u00f3n del inflamasoma NLRP3 favorecer\u00eda la adipog\u00e9nesis de\r\nc\u00e9lulas mesenquimales, lo que sugiere un rol en la formaci\u00f3n de IMAT. Se hipotetiza que la suplementaci\u00f3n\r\ncon &#946;HB durante la recuperaci\u00f3n de una lesi\u00f3n muscular aguda inhibe la diferenciaci\u00f3n adipog\u00e9nica de\r\nFAPs reduciendo la formaci\u00f3n de IMAT lo que acelera la reparaci\u00f3n y recuperaci\u00f3n funcional del tejido\r\nmuscular. Este efecto estar\u00eda mediado por la inhibici\u00f3n del inflamasoma NLRP3. Se inyectar\u00e1 una soluci\u00f3n\r\nhiperosm\u00f3tica al 25% de glicerol o salino en el m\u00fasculo tibial anterior en ratones con o sin suplementaci\u00f3n\r\nde 3 mg\/g &#946;HB durante 2 semanas post injuria. Se recolectar\u00e1 tejido muscular al 14dpi para an\u00e1lisis\r\nhistol\u00f3gico de IMAT. Paralelamente, se aislar\u00e1n FAPs del estroma vascular muscular al 3dpi. En FAPs\r\naisladas se evaluar\u00e1n prote\u00ednas de la v\u00eda NLPR3 inflamasoma y su capacidad adipog\u00e9nica en respuesta al\r\ntratamiento in-vitro con 3mM &#946;HB. Los resultados de esta propuesta nos permitir\u00e1n mostrar los efectos\r\nterap\u00e9uticos de la suplementaci\u00f3n dietar\u00eda con cuerpos cet\u00f3nicos en la funci\u00f3n y recuperaci\u00f3n muscular\r\npost da\u00f1o.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2023 - Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Comisi\u00f3n Sectorial de Investigaci\u00f3n Cient\u00edfica (CSIC), Universidad de La Rep\u00fablica de Uruguay<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27105\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27105\" aria-expanded=\"false\" aria-controls=\"collapse-27105\">\n                                            Investigadora Internacional Investigaci\u00f3n I+D &#8211; 2022 \u0093Site-specific: producci\u00f3n de intervenciones colaborativas y mediaci\u00f3n p\u00fablica desde la investigaci\u00f3n basada en las artes\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27105\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27105\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto busc\u00f3 implementar proyectos de arte colaborativo en diversos contextos sociales de Uruguay, para analizar sus dimensiones, oportunidades y dificultades.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Febrero 2023 - Febrero 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Sociedad Chilena de Nutrici\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25995\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            No Whey: L\u00e1cteos altos en prote\u00edna y ejercicio de resistencia para la mejora de la composici\u00f3n corporal y funci\u00f3n muscular de personas mayores.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25995\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25995\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La suplementaci\u00f3n con prote\u00ednas es una de las principales recomendaciones ante la practica regular de ejercicio f\u00edsico de resistencia (RT). En personas mayores, la necesidad de prote\u00edna se incrementa particularmente ante cambios fisiol\u00f3gicos y fisiopatol\u00f3gicos los que se asocian con la p\u00e9rdida de la funci\u00f3n y tejido muscular, por lo que su ingesta se hace de mayor relevancia en esta poblaci\u00f3n. Los l\u00e1cteos fermentados como el yogur, y en especial los con un contenido extra de prote\u00edna, han aumentado su popularidad y consumo en el mercado nacional. Su composici\u00f3n nutricional resulta de particular inter\u00e9s, dado su perfil de amino\u00e1cidos y en particular su alto contenido de Leucina, el que podr\u00eda compararse con los cl\u00e1sico suplementos de prote\u00edna recomendados para la ganancia y recuperaci\u00f3n muscular. Objetivo: Analizar el efecto en la composici\u00f3n corporal, perfil lip\u00eddico, condici\u00f3n fisica y funcionalidad muscular inducidas por ingesta de yogures altos en prote\u00edna versus prote\u00edna Whey junto un programa de resistencia muscular en personas mayores Hip\u00f3tesis: La ingesta de yogures altos en prote\u00edna conllevar\u00e1 a iguales o mayores ganancias de masa muscular, condici\u00f3n fisica y funcionalidad que las obtenidas con la ingesta de prote\u00ednas Whey en conjunto a un entrenamiento de resistencia en personas mayores. Metodolog\u00eda: Se reclutar\u00e1n 16 personas mayores (60-75 a\u00f1os), sanas y sin intolerancia a la lactosa para llevar a cabo 8 semanas de entrenamiento de resistencia (RT) muscular 3 veces por semana, los que de forma aleatoria ser\u00e1n suplementados con yogurt alto en prote\u00ednas (YPRT) o prote\u00edna Whey (WPRT). Al inicio y al t\u00e9rmino de la intervenci\u00f3n se evaluar\u00e1 la composici\u00f3n corporal mediante DEXA, fuerza muscular, consumo m\u00e1ximo de ox\u00edgeno y perfil lip\u00eddico. Resultados Esperados: Se espera que el grupo YPRT logre incrementos similares o superiores en la fuerza muscular, masa libre de grasa, perfil lip\u00eddico y disminuci\u00f3n de la masa grasa y que el grupo WPRT.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Febrero 2023 - Julio 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>DAAD - Alemania<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26681\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26681\" aria-expanded=\"false\" aria-controls=\"collapse-26681\">\n                                            ANTIBIOtic RESidues in Food: a comparative analysis in Bolivia, Italy, Ghana, and Nepal\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26681\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26681\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Antimicrobial resistance is a global phenomenon aggravated in recent decades by the inappropriate use of antimicrobials in human and veterinary medicine, the lack of prevention and control measures for infections associated with health care, and the limited development of new antimicrobials. It causes an increase in mortality, morbidity, and health spending. In this sense, the irrational use of antimicrobials in food-producing animals can reduce the effectiveness of those antibiotics in treating animal and human diseases. It also represents an additional risk for antimicrobial resistance by transferring antibiotics to food for human consumption and generating a new source of exposure. The residual antibiotics in food have been related to some adverse effects on human health, including allergic reactions, disruption of digestive system function, and chronic toxic effects from prolonged low-level exposure. It also represents a risk for the animals by jeopardizing the effectiveness of the necessary treatments.\r\n\r\nConsidering that, the project seeks to generate evidence regarding progress at the local level in regulatory issues and regarding the presence of antibiotics in food to raise awareness about the proper use of antibiotics in animals and humans and promote good practices[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Febrero 2023 - Julio 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>DAAD - Alemania<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26682\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26682\" aria-expanded=\"false\" aria-controls=\"collapse-26682\">\n                                            ECOH: Environment Care with a One Health approach &#8211; Water\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26682\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26682\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Water is an irreplaceable resource for developing socioeconomic activities and maintaining life on the planet. According to projections, water scarcity will increase, especially in those countries vulnerable to the effects of climate change and accelerated population growth. The negative impacts of the water deficit are already visible in some regions of the planet.\r\n\r\nThrough the ECOH-WATER project, we will develop capacities for the access and use of rainwater in educational centers in Guatemala and Bolivia for sustainable consumption, adapting to the impacts generated by climate change through strategies based on local needs. To do this, we will first diagnose the areas at risk of drought using Geographic Information Systems (GIS) to prioritize interventions. In the selected areas, we will develop an Action Research study with a strong participatory component to involve communities in implementing a rainwater harvesting system. Additionally, we will implement educational strategies for developing skills in seeking rational and sustainable water use. The project will establish alliances with local actors for the project's sustainability.\r\nThe search for strategies to access quality water for human, animal, and environmental consumption is a worldwide priority. It must involve the communities, raise awareness about natural resources and risk behaviors, and work collaboratively with decision-makers. On the other hand, the transdisciplinary work proposed in this project will allow the search for solutions with an integral vision. On the other hand, this project highlights the south-south collaboration to generate learning, enhance local resources, and move toward our region's sustainable development.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2023 - Enero 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26309\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Vinculaci\u00f3n para estrategias biotecnol\u00f3gicas y acad\u00e9micas de optimizaci\u00f3n del sistema suelo &#8211; planta, con miras a la productividad sustentable de alimentos y adaptaci\u00f3n de las regiones agr\u00edcolas a cambios globales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26309\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26309\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Promover una alianza nacional e internacional con el fin de fortalecer la red de colaboraci\u00f3n en el sistema suelo\u0096planta para la generaci\u00f3n sustentable e inocua de alimentos, mediante la aplicaci\u00f3n de estrategias biotecnol\u00f3gicas y acad\u00e9micas, con foco en el cambio clim\u00e1tico y prevenci\u00f3n de contaminantes emergentes, como las micotoxinas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2023 - Enero 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26774\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Vinculaci\u00f3n para estrategias biotecnol\u00f3gicas y acad\u00e9micas de optimizaci\u00f3n del sistema suelo &#8211; planta, con miras a la productividad sustentable de alimentos y adaptaci\u00f3n de las regiones agr\u00edcolas a cambios globales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26774\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26774\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Promover una alianza nacional e internacional con el fin de fortalecer la red de colaboraci\u00f3n en el sistema suelo\u0096planta para la generaci\u00f3n sustentable e inocua de alimentos, mediante la aplicaci\u00f3n de estrategias biotecnol\u00f3gicas y acad\u00e9micas, con foco en el cambio clim\u00e1tico y prevenci\u00f3n de contaminantes emergentes, como las micotoxinas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2023 - Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26757\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Legitimidad de las polic\u00edas en Chile: el efecto causal de la violencia y la corrupci\u00f3n desde una perspectiva multi-actor, longitudinal y multim\u00e9todos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26757\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26757\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetivo principal del proyecto es generar informaci\u00f3n sobre los niveles de legitimidad y justicia procedimental de las polic\u00edas entre la ciudadan\u00eda de Chile durante los pr\u00f3ximos 3 a\u00f1os, as\u00ed como entender los antecedentes que pueden llevar a un aumento o disminuci\u00f3n de las mismas.\r\nA partir del escenario actual posterior al estallido social, post pandemia y de aumento en los niveles de inseguridad ciudadana, resulta clave indagar en las percepciones que diferentes grupos sociales tienen sobre la legitimidad policial y las formas en que distintos eventos (corrupci\u00f3n, abuso policial, posibles reformas) impactan en ella en un contexto de alta incertidumbre y cambio. Esto \u00faltimo confiere a nuestro proyecto un potencial novedoso y transformador a nivel de evidencia emp\u00edrica hasta la fecha inexistente sobre c\u00f3mo se produce la legitimidad policial y c\u00f3mo \u00e9sta es un antecedente relevante para tener en cuenta en el marco de posibles reformas policiales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> CP22-E004<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2023 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Ciencia, Tecnolog\u00eda, Conocimiento e Innovaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26287\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Explorando el Ciclo del Agua, Sendero Educativo del Museo del Agua en la Regi\u00f3n de O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26287\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26287\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto de divulgaci\u00f3n cient\u00edfica en el Marco del Museo del Agua  cuya tem\u00e1tica principal es el ciclo del agua[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2023 - Enero 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26457\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia Laboratorio Ecosistemas de Humedales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26457\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26457\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto enfocado en el estudio de principales humedales de la regi\u00f3n de O'Higgins[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2023 - Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Easmus +<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26547\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            CSU4Change: Educational roadmap for transformative agency \u0096 connecting School, Community and University for social change\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26547\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26547\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The project seeks to achieve new understandings of how schools (teachers\/students), communities (homes\/community centers) and universities (researchers\/master students) can work together to build knowledge and engagement on contemporary issues of great importance for European societies. In this way young people will be able to take on new roles in our societies, as transformative agency towards merging social and environmental issues and their own future lives. One concrete result will be the development of a roadmap for social change and transformative agency, defined as a multimodal guideline. This will be built on projects and activities at schools in combination with results generated through the collaboration between partners on issues of transformative agency and ways of dealing with social change within schools. Another result of public interest will be emerging constellations of collaboration between educational partners and countries.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 2022.05941.PTDC<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2023 - Diciembre 2027<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Funda\u00e7ao para a Ciencia e Tecnolog\u00eda (Portugal)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26755\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            LUSO: The Past in the Present: Antecedents and Consequences of Luso-Tropicalism for the Legitimation of Contemporary Social and Racial Inequality\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26755\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26755\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The general objective of LUSO is to analyze how the organizing dimensions of colonial ideological thinking persist and operate in Portuguese society, and what function they have in legitimizing discriminatory attitudes and behaviors toward formerly colonized groups. The research questions will be addressed in four working packages (WP). Specifically, LUSO will (1) develop and validate a new instrument measuring the organizing dimensions of Luso-tropicalism, as a postcolonial ideological thinking, which we propose to be organized in four latent factors (WP1); (2) test the social normativity of Luso-tropicalism (WP2); (3) test if it operates as a legitimizing myth within the general framework of intergroup ideologies (WP3), by proposing that it can dampen support to inclusive social policies (i.e., a suppression effect) and facilitate discriminatory attitudes and behaviors toward disadvantaged people from formerly colonized groups (i.e., a foster process); (4) examine the social diffusion of these assumptions with a sample of the Portuguese population (WP4), while testing potential moderators of those relationships, namely socialization patterns (i.e., intergenerational differences) and group status (high SES vs low SES). LUSO will conduct a multi-method research program that includes qualitative and quantitative studies, correlational and experimental research designs, and an online survey. LUSO will make a substantial contribution to the study of the psychosocial processes of colonial legacy in the national context and will significantly advance the knowledge about the structure of postcolonial ideological thinking in the international scene.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2023 - Marzo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26983\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estado, seguridad, violencia y zona gris en M\u00e9xico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26983\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26983\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]proyecto busca comprender la variabilidad de la relaci\u00f3n entre el Estado y los colectivos de particulares que tienen por objeto cumplir funciones de seguridad a nivel local.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2023 - Julio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26462\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Realidad de las mujeres en las Ciencias de la Ingenier\u00eda en la regi\u00f3n de O\u0092Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26462\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26462\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El presente trabajo, financiado por la Direcci\u00f3n de Equidad de G\u00e9nero y Diversidades\r\nde la Universidad de O\u0092Higgins (Convocatoria 2022), busca evaluar las principales\r\nmotivaciones y dificultades de las mujeres para ingresar a carreras de las Ciencias de\r\nla Ingenier\u00eda, titularse y continuar una carrera acad\u00e9mica en la Regi\u00f3n de O\u0092Higgins.\r\nLa Universidad Estatal de O\u0092Higgins es una instituci\u00f3n de 7 a\u00f1os que desde sus inicios\r\nha promovido pol\u00edticas para la equidad de g\u00e9nero, sin embargo estas medidas\r\npareciera ser a\u00fan insuficientes o no se le ha dado un seguimiento para ver su\r\nverdadero impacto en esta materia.\r\nLa diferencia en el n\u00famero de matr\u00edculas de mujeres vs hombres en carreras de\r\nCiencias de la Ingenier\u00eda de Universidades chilenas es abismante, a pesar de la no\r\nexistencia de diferencias inherentes\/innatas entre hombres y mujeres que expliquen\r\nlas brechas en los aprendizajes o trayectorias acad\u00e9micas en las matem\u00e1ticas (\r\nBakker et al., 2021; Kersey et al., 2019; Lachance & Mazzocco, 2006; Spelke, 2005).\r\nSeg\u00fan Ing2030 (2018), el aumento de mujeres en carreras de ingenier\u00eda en Chile no\r\n\r\nha sido significativo en un lapso de 10 a\u00f1os: 20% el a\u00f1o 2004 y 24% el a\u00f1o 2014.\r\nTanto as\u00ed que en el a\u00f1o 2019, el 7% de las mujeres que se titularon de pregrado en\r\nChile, lo hicieron en las \u00e1reas de ciencia, tecnolog\u00eda, ingenier\u00eda y matem\u00e1ticas (STEM),\r\nsiendo el pa\u00eds con el porcentaje m\u00e1s bajo de los miembros de la OCDE (Ministerio de\r\nCiencia, Tecnolog\u00eda, Conocimiento e Innovaci\u00f3n, 2022).\r\nPara llevar a cabo este estudio se han usado metodolog\u00edas cuantitativas y\r\ncualitativas. El estudio cuantitativo se realiza mediante encuestas online mientras que\r\nel estudio cualitativo es a trav\u00e9s del desarrollo de Focus group. Se analizaron 468\r\nencuestas online a estudiantes de ense\u00f1anza media de la Regi\u00f3n de O\u0092Higgins, 94\r\nencuestas a estudiantes de las carreras de Ingenier\u00eda de la Universidad de O\u0092Higgins y\r\n25 encuestas a acad\u00e9micos(as) e investigadores del Instituto de Ciencias de la\r\nIngenier\u00eda de la Universidad de O\u0092Higgins. Adicionalmente, se analizaron los\r\nresultados de 3 focus groups a alumnas de ense\u00f1anza media de la comuna de\r\nRancagua y 3 focus groups a alumnas de las carreras de Ingenier\u00eda de la Universidad\r\nde O\u0092Higgins.\r\nDentro de los resultados se observa que un 83% de los y las estudiantes de\r\nense\u00f1anza media de la Regi\u00f3n de O\u0092Higgins considera que tanto hombres como\r\nmujeres avanzan con igual rapidez en sus carreras, un 84% de las y los estudiantes\r\nde carreras de Ingenier\u00eda de la Universidad de O\u0092Higgins considera que mujeres y\r\nhombres tienen igualdad de avance en sus carreras, mientras que un 76% de\r\nacad\u00e9micos(as) e investigadores(as) estima que los hombres avanzan m\u00e1s r\u00e1pido en\r\nsu carrera. Se constat\u00f3 que estudiantes de ense\u00f1anza media, estudiantes de las\r\ncarreras de ingenier\u00eda y acad\u00e9micas e investigadoras de la Regi\u00f3n de O\u0092Higgins\r\nexperimentan brechas y barreras, sumado a la falta de confianza en sus capacidades\r\ny logros (S\u00edndrome de la Impostora; Paterson & Vincent-Akpu, 2021). Adicionalmente,\r\na pesar de considerar que en la Regi\u00f3n de O\u0092Higgins y en la Universidad de O\u0092Higgins\r\nse promueve una cultura para la igualdad de g\u00e9nero, el grupo en estudio tiene la\r\ncreencia que las estudiantes y acad\u00e9micas de las Geociencias y Ciencias de la\r\nIngenier\u00eda son m\u00e1s propensas a sufrir acoso. Asimismo, las estudiantes y cient\u00edficas\r\nenfrentan importantes dificultades para compatibilizar la vida familiar y laboral.\r\nA trav\u00e9s de este estudio buscamos visibilizar las principales dificultades que enfrentan\r\nestudiantes e investigadoras de esta \u00e1rea durante el desarrollo de su carrera. Tomar\r\nconciencia de la realidad de las mujeres en \u00e1reas STEM en la Regi\u00f3n de O\u0092Higgins\r\npermitir\u00e1 tomar medidas m\u00e1s eficientes y eficaces tanto para la atracci\u00f3n como para\r\nevitar la fuga y\/o estancamiento de estudiantes y cient\u00edficas con alto potencial,\r\npermitiendo un acceso m\u00e1s igualitario en carreras STEM y un desarrollo en un espacio\r\nseguro y de respeto.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI220056<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26581\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Formaci\u00f3n docente en la era de los datos y la informaci\u00f3n: potenciando la transformaci\u00f3n digital desde la educaci\u00f3n estad\u00edstica\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26581\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26581\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Durante las \u00faltimas d\u00e9cadas, el dominio de la estad\u00edstica ha sido destacado como una\r\ncompetencia clave para desenvolverse activa y razonadamente en la era de los datos y\r\nla informaci\u00f3n. Por ello, la estad\u00edstica se incorporado al curr\u00edculum de matem\u00e1ticas\r\ndurante todo el recorrido escolar. No obstante, en las escuelas es com\u00fan que los\r\nprofesores den un car\u00e1cter marginal a este tema dentro del curr\u00edculum de matem\u00e1ticas\r\ny m\u00e1s a\u00fan, en el caso de Chile, existe evidencia que hasta minimizan su ense\u00f1anza a\r\nrealizar c\u00e1lculos o simplemente la ignoran.\r\nEn consecuencia, en este proyecto nos planteamos abordar esta problem\u00e1tica por medio\r\nde una reorientaci\u00f3n de la formaci\u00f3n docente, inicial y continua, en el contenido de\r\nestad\u00edstica y su ense\u00f1anza, donde se destaca la importancia de conceptualizar a la\r\nestad\u00edstica como un proceso de investigaci\u00f3n que persigue responder interrogantes a\r\npartir de los datos, para lo cual se requiere un fuerte apoyo tecnol\u00f3gico. Para ello, el\r\nobjetivo de este proyecto es caracterizar experiencias de ense\u00f1anza y aprendizaje de la\r\nestad\u00edstica en la formaci\u00f3n inicial y continua de profesores de matem\u00e1ticas chilenos,\r\nque promuevan una transformaci\u00f3n digital en las pr\u00e1cticas de aula de este contenido y\r\naborden tem\u00e1ticas socialmente relevantes.\r\nDesde un paradigma cualitativo, se asume una concepci\u00f3n de la investigaci\u00f3n basada\r\nen el dise\u00f1o, considerando las etapas cl\u00e1sicas de este enfoque: preliminar, dise\u00f1o,\r\nimplementaci\u00f3n y evaluaci\u00f3n retrospectiva. Posteriormente, se crear\u00e1 una p\u00e1gina web\r\nen la cual est\u00e9 disponible gratuitamente el material creado, tanto en la formaci\u00f3n inicial\r\ncomo continua, donde se explicite las formas de implementar y\/o se muestren v\u00eddeos\r\nde algunas pr\u00e1cticas exitosas.\r\nDe esta forma, pretendemos avanzar en la l\u00ednea de una educaci\u00f3n estad\u00edstica fortalecida\r\ndesde elementos te\u00f3ricos-did\u00e1cticos que permitan al profesor en formaci\u00f3n y en\r\nejercicio avanzar con mayor seguridad en su ense\u00f1anza.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2023 - Julio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26852\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Realidad de las mujeres en las Ciencias de la Ingenier\u00eda en la regi\u00f3n de O\u0092Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26852\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26852\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El presente trabajo, financiado por la Direcci\u00f3n de Equidad de G\u00e9nero y Diversidades\r\nde la Universidad de O\u0092Higgins (Convocatoria 2022), busca evaluar las principales\r\nmotivaciones y dificultades de las mujeres para ingresar a carreras de las Ciencias de\r\nla Ingenier\u00eda, titularse y continuar una carrera acad\u00e9mica en la Regi\u00f3n de O\u0092Higgins.\r\nLa Universidad Estatal de O\u0092Higgins es una instituci\u00f3n de 7 a\u00f1os que desde sus inicios\r\nha promovido pol\u00edticas para la equidad de g\u00e9nero, sin embargo estas medidas\r\npareciera ser a\u00fan insuficientes o no se le ha dado un seguimiento para ver su\r\nverdadero impacto en esta materia.\r\nLa diferencia en el n\u00famero de matr\u00edculas de mujeres vs hombres en carreras de\r\nCiencias de la Ingenier\u00eda de Universidades chilenas es abismante, a pesar de la no\r\nexistencia de diferencias inherentes\/innatas entre hombres y mujeres que expliquen\r\nlas brechas en los aprendizajes o trayectorias acad\u00e9micas en las matem\u00e1ticas (\r\nBakker et al., 2021; Kersey et al., 2019; Lachance & Mazzocco, 2006; Spelke, 2005).\r\nSeg\u00fan Ing2030 (2018), el aumento de mujeres en carreras de ingenier\u00eda en Chile no\r\n\r\nha sido significativo en un lapso de 10 a\u00f1os: 20% el a\u00f1o 2004 y 24% el a\u00f1o 2014.\r\nTanto as\u00ed que en el a\u00f1o 2019, el 7% de las mujeres que se titularon de pregrado en\r\nChile, lo hicieron en las \u00e1reas de ciencia, tecnolog\u00eda, ingenier\u00eda y matem\u00e1ticas (STEM),\r\nsiendo el pa\u00eds con el porcentaje m\u00e1s bajo de los miembros de la OCDE (Ministerio de\r\nCiencia, Tecnolog\u00eda, Conocimiento e Innovaci\u00f3n, 2022).\r\nPara llevar a cabo este estudio se han usado metodolog\u00edas cuantitativas y\r\ncualitativas. El estudio cuantitativo se realiza mediante encuestas online mientras que\r\nel estudio cualitativo es a trav\u00e9s del desarrollo de Focus group. Se analizaron 468\r\nencuestas online a estudiantes de ense\u00f1anza media de la Regi\u00f3n de O\u0092Higgins, 94\r\nencuestas a estudiantes de las carreras de Ingenier\u00eda de la Universidad de O\u0092Higgins y\r\n25 encuestas a acad\u00e9micos(as) e investigadores del Instituto de Ciencias de la\r\nIngenier\u00eda de la Universidad de O\u0092Higgins. Adicionalmente, se analizaron los\r\nresultados de 3 focus groups a alumnas de ense\u00f1anza media de la comuna de\r\nRancagua y 3 focus groups a alumnas de las carreras de Ingenier\u00eda de la Universidad\r\nde O\u0092Higgins.\r\nDentro de los resultados se observa que un 83% de los y las estudiantes de\r\nense\u00f1anza media de la Regi\u00f3n de O\u0092Higgins considera que tanto hombres como\r\nmujeres avanzan con igual rapidez en sus carreras, un 84% de las y los estudiantes\r\nde carreras de Ingenier\u00eda de la Universidad de O\u0092Higgins considera que mujeres y\r\nhombres tienen igualdad de avance en sus carreras, mientras que un 76% de\r\nacad\u00e9micos(as) e investigadores(as) estima que los hombres avanzan m\u00e1s r\u00e1pido en\r\nsu carrera. Se constat\u00f3 que estudiantes de ense\u00f1anza media, estudiantes de las\r\ncarreras de ingenier\u00eda y acad\u00e9micas e investigadoras de la Regi\u00f3n de O\u0092Higgins\r\nexperimentan brechas y barreras, sumado a la falta de confianza en sus capacidades\r\ny logros (S\u00edndrome de la Impostora; Paterson & Vincent-Akpu, 2021). Adicionalmente,\r\na pesar de considerar que en la Regi\u00f3n de O\u0092Higgins y en la Universidad de O\u0092Higgins\r\nse promueve una cultura para la igualdad de g\u00e9nero, el grupo en estudio tiene la\r\ncreencia que las estudiantes y acad\u00e9micas de las Geociencias y Ciencias de la\r\nIngenier\u00eda son m\u00e1s propensas a sufrir acoso. Asimismo, las estudiantes y cient\u00edficas\r\nenfrentan importantes dificultades para compatibilizar la vida familiar y laboral.\r\nA trav\u00e9s de este estudio buscamos visibilizar las principales dificultades que enfrentan\r\nestudiantes e investigadoras de esta \u00e1rea durante el desarrollo de su carrera. Tomar\r\nconciencia de la realidad de las mujeres en \u00e1reas STEM en la Regi\u00f3n de O\u0092Higgins\r\npermitir\u00e1 tomar medidas m\u00e1s eficientes y eficaces tanto para la atracci\u00f3n como para\r\nevitar la fuga y\/o estancamiento de estudiantes y cient\u00edficas con alto potencial,\r\npermitiendo un acceso m\u00e1s igualitario en carreras STEM y un desarrollo en un espacio\r\nseguro y de respeto.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2023 - Julio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27034\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Realidad de las mujeres en las Ciencias de la Ingenier\u00eda en la regi\u00f3n de O\u0092Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27034\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27034\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El presente trabajo, financiado por la Direcci\u00f3n de Equidad de G\u00e9nero y Diversidades\r\nde la Universidad de O\u0092Higgins (Convocatoria 2022), busca evaluar las principales\r\nmotivaciones y dificultades de las mujeres para ingresar a carreras de las Ciencias de\r\nla Ingenier\u00eda, titularse y continuar una carrera acad\u00e9mica en la Regi\u00f3n de O\u0092Higgins.\r\nLa Universidad Estatal de O\u0092Higgins es una instituci\u00f3n de 7 a\u00f1os que desde sus inicios\r\nha promovido pol\u00edticas para la equidad de g\u00e9nero, sin embargo estas medidas\r\npareciera ser a\u00fan insuficientes o no se le ha dado un seguimiento para ver su\r\nverdadero impacto en esta materia.\r\nLa diferencia en el n\u00famero de matr\u00edculas de mujeres vs hombres en carreras de\r\nCiencias de la Ingenier\u00eda de Universidades chilenas es abismante, a pesar de la no\r\nexistencia de diferencias inherentes\/innatas entre hombres y mujeres que expliquen\r\nlas brechas en los aprendizajes o trayectorias acad\u00e9micas en las matem\u00e1ticas (\r\nBakker et al., 2021; Kersey et al., 2019; Lachance & Mazzocco, 2006; Spelke, 2005).\r\nSeg\u00fan Ing2030 (2018), el aumento de mujeres en carreras de ingenier\u00eda en Chile no\r\n\r\nha sido significativo en un lapso de 10 a\u00f1os: 20% el a\u00f1o 2004 y 24% el a\u00f1o 2014.\r\nTanto as\u00ed que en el a\u00f1o 2019, el 7% de las mujeres que se titularon de pregrado en\r\nChile, lo hicieron en las \u00e1reas de ciencia, tecnolog\u00eda, ingenier\u00eda y matem\u00e1ticas (STEM),\r\nsiendo el pa\u00eds con el porcentaje m\u00e1s bajo de los miembros de la OCDE (Ministerio de\r\nCiencia, Tecnolog\u00eda, Conocimiento e Innovaci\u00f3n, 2022).\r\nPara llevar a cabo este estudio se han usado metodolog\u00edas cuantitativas y\r\ncualitativas. El estudio cuantitativo se realiza mediante encuestas online mientras que\r\nel estudio cualitativo es a trav\u00e9s del desarrollo de Focus group. Se analizaron 468\r\nencuestas online a estudiantes de ense\u00f1anza media de la Regi\u00f3n de O\u0092Higgins, 94\r\nencuestas a estudiantes de las carreras de Ingenier\u00eda de la Universidad de O\u0092Higgins y\r\n25 encuestas a acad\u00e9micos(as) e investigadores del Instituto de Ciencias de la\r\nIngenier\u00eda de la Universidad de O\u0092Higgins. Adicionalmente, se analizaron los\r\nresultados de 3 focus groups a alumnas de ense\u00f1anza media de la comuna de\r\nRancagua y 3 focus groups a alumnas de las carreras de Ingenier\u00eda de la Universidad\r\nde O\u0092Higgins.\r\nDentro de los resultados se observa que un 83% de los y las estudiantes de\r\nense\u00f1anza media de la Regi\u00f3n de O\u0092Higgins considera que tanto hombres como\r\nmujeres avanzan con igual rapidez en sus carreras, un 84% de las y los estudiantes\r\nde carreras de Ingenier\u00eda de la Universidad de O\u0092Higgins considera que mujeres y\r\nhombres tienen igualdad de avance en sus carreras, mientras que un 76% de\r\nacad\u00e9micos(as) e investigadores(as) estima que los hombres avanzan m\u00e1s r\u00e1pido en\r\nsu carrera. Se constat\u00f3 que estudiantes de ense\u00f1anza media, estudiantes de las\r\ncarreras de ingenier\u00eda y acad\u00e9micas e investigadoras de la Regi\u00f3n de O\u0092Higgins\r\nexperimentan brechas y barreras, sumado a la falta de confianza en sus capacidades\r\ny logros (S\u00edndrome de la Impostora; Paterson & Vincent-Akpu, 2021). Adicionalmente,\r\na pesar de considerar que en la Regi\u00f3n de O\u0092Higgins y en la Universidad de O\u0092Higgins\r\nse promueve una cultura para la igualdad de g\u00e9nero, el grupo en estudio tiene la\r\ncreencia que las estudiantes y acad\u00e9micas de las Geociencias y Ciencias de la\r\nIngenier\u00eda son m\u00e1s propensas a sufrir acoso. Asimismo, las estudiantes y cient\u00edficas\r\nenfrentan importantes dificultades para compatibilizar la vida familiar y laboral.\r\nA trav\u00e9s de este estudio buscamos visibilizar las principales dificultades que enfrentan\r\nestudiantes e investigadoras de esta \u00e1rea durante el desarrollo de su carrera. Tomar\r\nconciencia de la realidad de las mujeres en \u00e1reas STEM en la Regi\u00f3n de O\u0092Higgins\r\npermitir\u00e1 tomar medidas m\u00e1s eficientes y eficaces tanto para la atracci\u00f3n como para\r\nevitar la fuga y\/o estancamiento de estudiantes y cient\u00edficas con alto potencial,\r\npermitiendo un acceso m\u00e1s igualitario en carreras STEM y un desarrollo en un espacio\r\nseguro y de respeto.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> CS2018-7993<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2023 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Fundaci\u00f3n S\u00e9neca Agencia de Ciencia y Tecnolog\u00eda de la Regi\u00f3n de Murcia<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27050\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27050\" aria-expanded=\"false\" aria-controls=\"collapse-27050\">\n                                            S\u00edntesis y caracterizaci\u00f3n de sistemas de liberaci\u00f3n basados en quitosano y estudio de efectos inmunomoduladores en peces de acuicultura (Chitfish)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27050\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27050\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]S\u00edntesis y caracterizaci\u00f3n de sistemas de liberaci\u00f3n basados en quitosano y estudio de efectos inmunomoduladores en peces de acuicultura (Chitfish)[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2022 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Centro Interuniversitario de Envejecimiento Saludable<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26000\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Caracterizaci\u00f3n de la capacidad funcional y condici\u00f3n f\u00edsica de personas mayores de siete comunas de la zona centro-sur de Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26000\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26000\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto que involucra a 7 universidades p\u00fablicas chilenas donde evaluaremos la condici\u00f3n f\u00edsica y capacidad funcional de personas mayores en siete diferentes comunas de la zona centro-sur de Chile y su asociaci\u00f3n con antecedentes bio-demogr\u00e1ficos.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> CP22-P067<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2022 - Diciembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Ciencia, Tecnolog\u00eda, Conocimiento e Innovaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26850\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            GeoXplora Crusoe\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26850\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26850\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto GeoXplora Crusoe tiene como objetivo el desarrollo e implementaci\u00f3n de una aplicaci\u00f3n de realidad aumentada y geolocalizaci\u00f3n, con contenido geol\u00f3gico, para la isla de Robinson Crusoe (Archipi\u00e9lago Juan Fern\u00e1ndez). Se trata de desarrollar una aplicaci\u00f3n para dispositivos m\u00f3viles inteligentes (Smartphones -  tecnolog\u00eda iOs y Android) que permita entregar informaci\u00f3n fundamental sobre geolog\u00eda, adem\u00e1s de una visualizaci\u00f3n in situ simple e interactiva de los diferentes y m\u00e1s importantes hitos geol\u00f3gicos de la isla. \r\n\r\nLa aplicaci\u00f3n permitir\u00e1 la identificaci\u00f3n de los usuarios mediante registro, la geolocalizaci\u00f3n de sendero, y el reconocimiento de 13 hitos geol\u00f3gicos a lo largo de la isla. Dispondr\u00e1 de c\u00e1psulas multimediales inclusivas, con audios desarrollados para personas invidentes y videos con subt\u00edtulos para personas sordas, de manera que puedan acceder a los contenidos de la app y as\u00ed promover la geodifusi\u00f3n en un sector usualmente dejado de lado en las innovaciones tecnol\u00f3gicas. Las c\u00e1psulas estar\u00e1n en espa\u00f1ol e ingl\u00e9s (videos, infograf\u00edas y\/o sonidos), basadas en realidad aumentada y de despliegue atractivo de informaci\u00f3n, m\u00e1s se\u00f1al\u00e9tica no invasiva con iconograf\u00eda, mediante QRs y paneles informativos f\u00edsicos a lo largo de los senderos. Se incentivar\u00e1 que los usuarios de la aplicaci\u00f3n tomen fotograf\u00edas que indiquen la fecha y lugar durante su trayecto por los senderos con el fin de ser compartidas en redes sociales y as\u00ed promover el valor geol\u00f3gico de la isla. \r\n\r\nEsta app se basa en la necesidad de vincular principalmente a la poblaci\u00f3n de Juan Fern\u00e1ndez, de 12 a\u00f1os en adelante, y a los turistas que llegan a la isla con el valor de la geodiversidad y del territorio de lugares emblem\u00e1ticos, resaltando las experiencias de senderismo y potenciando un turismo cient\u00edfico. Su desarrollo, implementaci\u00f3n y uso permitir\u00e1 dotar a la comunidad de una base cient\u00edfica en materia geol\u00f3gica, hasta ahora poco conocida, para que puedan comprender de mejor manera el territorio que habitan, promover su conservaci\u00f3n y a su vez ofrecer al turismo experiencias de mayor calidad. \r\n\r\nLa experiencia a trav\u00e9s de la app permitir\u00e1 a los usuarios convertirse en exploradores de la ciencia, incentivando el pensamiento cr\u00edtico desde la exploraci\u00f3n y potenciando la curiosidad, haciendo que el recorrido por la isla sea una experiencia \u0093geomemorable\u0094.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 13220097<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2022 - Diciembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26527\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            A new probabilistic paradigm for modelling optimal decision-making processes under uncertainty\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26527\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26527\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]This project aims to develop a new probabilistic paradigm for modeling optimal decision-making under uncertainty.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> TDP220008<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2022 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27051\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Producci\u00f3n y caracterizaci\u00f3n de cuerpos de inclusi\u00f3n recombinantes para ser usados como ant\u00edgenos en un prototipo de vacuna contra Piscirikettsia salmonis\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27051\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27051\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Piscirickettsia salmonis una de las enfermedades m\u00e1s graves y perjudiciales que afecta a la industria salmonera en Chile, provocando altas mortalidades con p\u00e9rdidas econ\u00f3micas de USD 700 al a\u00f1o.  Esta bacteria intracelular produce la Piscirickettsiosis enfermedad tratada principalmente con vacunas y antibi\u00f3ticos. Sin embargo, y a pesar de existir 34 vacunas comerciales disponibles, estas no han demostrado controlar totalmente los brotes epid\u00e9micos. Por otro lado, los antibi\u00f3ticos logran controlar la enfermedad, pero disminuyen el valor del producto debido a la connotaci\u00f3n negativa por el riesgo a la salud tanto de animales como humanos. En base a esta problem\u00e1tica es que surge la necesidad de desarrollar nuevos m\u00e9todos profil\u00e1cticos que contribuyan al control de este pat\u00f3geno que pone en riesgo la sustentabilidad de la industria salmonera en Chile. Un nuevo m\u00e9todo profil\u00e1ctico son las nanoprote\u00ednas quim\u00e9ricas, agregados de prote\u00ednas que son liberadas gradualmente en el tiempo aumentando su efecto protector, no necesitan de encapsulaci\u00f3n, su producci\u00f3n es escalable en biorreactores, son liofilizables, y son altamente estables a condiciones adveras de temperatura y pH. En mi tesis de doctorado en conjunto con la empresa Nanoprot proponemos el desarrollo y producci\u00f3n de un prototipo de baja resoluci\u00f3n de una vacuna en base a nanoprote\u00ednas quim\u00e9ricas para combatir brotes de P. salmonis. Nuestro primer objetivo es desarrollar nanoprote\u00ednas en base a prote\u00ednas formadas por regiones altamente inmunog\u00e9nicas y antig\u00e9nicas de distintas secuencias aminoac\u00eddicas de P. salmonis. Su conformaci\u00f3n proteica en conjunto con una lenta liberaci\u00f3n en el tiempo permitir\u00e1 aumentar la protecci\u00f3n en salm\u00f3nidos frente a esta bacteria, sin necesidad de vacunaci\u00f3n de refuerzo. Luego del dise\u00f1o, se seleccionar\u00e1 la nanoprote\u00edna quim\u00e9rica que cumpla con las caracter\u00edsticas de eficiencia de producci\u00f3n, funcionalidad y capacidad de modular la respuesta inmune en base a ensayos in vitro en macr\u00f3fagos de salm\u00f3n del Atl\u00e1ntico. Finalmente, se evaluar\u00e1 en bioensayo si generan una respuesta inmune adaptativo-prolongada en el tiempo en salm\u00f3n del Atl\u00e1ntico. Los resultados obtenidos ser\u00e1n: (1) prototipo de baja resoluci\u00f3n de una vacuna; (2) Know-how relativo a la formulaci\u00f3n del producto; (3) estudio de patentabilidad y\/o licenciamiento del prototipo; (4) publicaci\u00f3n de art\u00edculo cient\u00edfico y difusi\u00f3n; (5) levantamiento de recursos para continuidad de proyecto; y (6) entrega de tesis y prototipo a empresa. El proyecto de tesis es parte de las l\u00edneas de desarrollo de Nanoprot; se enmarcan en las necesidades de la empresa del desarrollo de investigaci\u00f3n de I+D+i que permita brindar una soluci\u00f3n innovadora para el control de la Piscirickettiosis. Nanoprot es una start-up que nace en la PUCV, por lo que existe una estrecha vinculaci\u00f3n entre el tesista, tutor y el mentor en el desarrollo de la propuesta. La creaci\u00f3n de este prototipo nos brindar\u00e1 la oportunidad de postular a nuevos fondos que den continuidad a este trabajo y que permitan mi contrataci\u00f3n por parte de la empresa. Asimismo, aportar\u00e1 una soluci\u00f3n innovadora a la industria salmonera disminuyendo las mortalidades, p\u00e9rdidas econ\u00f3micas y uso de antibi\u00f3ticos asociadas a P. salmonis.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>CONICET Argentina<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26986\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Las acciones colectivas de violencia punitiva. El caso de Argentina en el contexto del vigilantismo en Latinoam\u00e9rica\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26986\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26986\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Materia Espec\u00edfica: El proyecto busca comprender las particularidades de la realidad Argentina, dentro del contexto latinoamericano, respecto de una serie de acciones que se incluyen en el repertorio de acci\u00f3n propio del vigilantismo[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2022 - Noviembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26147\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Primeros pasos humanos en Am\u00e9rica del Sur: caminando entre Gonfoterios\u0094 \u0096 Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26147\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26147\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Renovaci\u00f3n proyecto de excavaci\u00f3n arqueol\u00f3gica y paleontol\u00f3gica en San Vicente de Tagua Tagua[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> Resoluci\u00f3n exenta N\u00b0 2848-2022<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2022 - Diciembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Servicio Nacional de la Discapacidad (SENADIS)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26022\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Servicios de Asesor\u00eda y Acompa\u00f1amiento en la Instalaci\u00f3n de Incubadoras de Cooperativas Inclusivas a Municipalidades adjudicatarias de la Modalidad Continuidad de la Estrategia de Desarrollo Local Inclusivo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26022\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26022\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Convenio de Transferencia Directa de recursos para la Ejecuci\u00f3n de Servicios de Asesor\u00eda y Acompa\u00f1amiento en la Instalaci\u00f3n de Incubadoras de Cooperativas Inclusivas a Municipalidades adjudicatarias de la Modalidad Continuidad de la Estrategia de Desarrollo Local Inclusivo.\r\n\r\nCoordinaci\u00f3n de la Red de Cooperativas Inclusivas de Chile, REFICOOP.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> Resoluci\u00f3n exenta N\u00b0 2848-2022<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2022 - Diciembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Servicio Nacional de la Discapacidad (SENADIS)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26687\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Servicios de Asesor\u00eda y Acompa\u00f1amiento en la Instalaci\u00f3n de Incubadoras de Cooperativas Inclusivas a Municipalidades adjudicatarias de la Modalidad Continuidad de la Estrategia de Desarrollo Local Inclusivo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26687\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26687\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Convenio de Transferencia Directa de recursos para la Ejecuci\u00f3n de Servicios de Asesor\u00eda y Acompa\u00f1amiento en la Instalaci\u00f3n de Incubadoras de Cooperativas Inclusivas a Municipalidades adjudicatarias de la Modalidad Continuidad de la Estrategia de Desarrollo Local Inclusivo.\r\n\r\nCoordinaci\u00f3n de la Red de Cooperativas Inclusivas de Chile, REFICOOP.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> Resoluci\u00f3n exenta N\u00b0 2848-2022<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2022 - Diciembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Servicio Nacional de la Discapacidad (SENADIS)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26839\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Servicios de Asesor\u00eda y Acompa\u00f1amiento en la Instalaci\u00f3n de Incubadoras de Cooperativas Inclusivas a Municipalidades adjudicatarias de la Modalidad Continuidad de la Estrategia de Desarrollo Local Inclusivo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26839\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26839\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Convenio de Transferencia Directa de recursos para la Ejecuci\u00f3n de Servicios de Asesor\u00eda y Acompa\u00f1amiento en la Instalaci\u00f3n de Incubadoras de Cooperativas Inclusivas a Municipalidades adjudicatarias de la Modalidad Continuidad de la Estrategia de Desarrollo Local Inclusivo.\r\n\r\nCoordinaci\u00f3n de la Red de Cooperativas Inclusivas de Chile, REFICOOP.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> IDI40048446-0<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26269\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia Laboratorio Ecosistemas de Humedales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26269\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26269\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Fondo de Innovaci\u00f3n para la Competitividad - FIC2023- 6ta regi\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> IDI40048446-0<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26377\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia Laboratorio Ecosistemas de Humedales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26377\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26377\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Fondo de Innovaci\u00f3n para la Competitividad - FIC2023- 6ta regi\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> Proyecto Fondecyt Regular 1221107<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26742\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Legitimation, ideology, and contentious collective action\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26742\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26742\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Materia Espec\u00edfica: Este proyecto de investigaci\u00f3n tiene como objetivo desentra\u00f1ar las interrelaciones entre: (a) la legitimaci\u00f3n del statu quo en diferentes dimensiones contenciosas, y; (b) protestas y otras formas de acci\u00f3n colectiva orientadas hacia el cambio social. Nuestro caso de estudio es la crisis de legitimaci\u00f3n de las instituciones econ\u00f3micas y pol\u00edticas chilenas, y la larga ola de protestas y movilizaciones sociales que ha vivido el pa\u00eds en los \u00faltimos a\u00f1os.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ATE220029<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2022 - Noviembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27046\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Water energy food nexus for urban  areas of central chile(wef-chile)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27046\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27046\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Ensuring a secure and sustainable water supply is a major challenge for the 21th century. The population growth,\r\nurbanization, and industrial\/agriculture expansion need an increasing water provision, delivered at a constant rate.\r\nFurthermore, under the current climate change and droughts scenarios, with the depletion of surface water storage\r\nand quality, groundwater resources are fulfilling the growing water requirement for food and energy production.\r\nEstimated data indicate that in the 2010 &#769;s, groundwater supplies 36% of potable water, 43% of irrigated agriculture\r\n(considering the baseflow feeding rivers, this percentage is higher), and 24% of direct industrial water supply. The\r\ngroundwater use is growing at a rate of 5% per year, and by 2050, the food and water demand will increase by 50%.\r\nHowever, the misconceiving and oversimplification of conceptual models about groundwater recharge points out\r\nthat around 25% of its use is unsustainable. These considerations highlight how identifying innovative and\r\nintegrated solutions to tackle the intertwined challenges of water and climate change as well as the complex\r\ninterlink between water, energy, and food supply systems under current climate variability is an increasingly major\r\nimperative for the near future.\r\nThe study of the water\u0096energy\u0096food nexus has received increasing attention from the global scientific community,\r\nfocusing on how these three elements can interact sustainably. The interdependence of water resources, energy\r\ngeneration, and food production depends on reliable data and information on these resources. In this context,\r\ngroundwater can serve to supply water and energy demand, strengthening food security and reducing fossil fuel\r\nenergy dependence. Aquifers can provide water and geothermal energy, a clean baseload resource independent\r\nfrom weather conditions, which could significantly contribute to energy needs, improved air quality and food\r\nproduction as well as to reach the decarbonization targets. This combined aquifer\u0092s use improvement could be\r\nespecially relevant in urban areas where more than 50% of the world\u0092s population lives and which is forecast to\r\nincrease to 68% by 2050 with associated greenhouse gas emissions growth up to 80%.\r\nAquifers are important heat reservoirs because groundwater flow is a powerful heat carrier, which can help achieve\r\na more sustainable water-energy-food management, representing a major challenge to improving water, energy,\r\nand food security. In fact, by 2050, the demand for water and food is expected to increase by 60%, and the energy\r\ndemand will be practically doubled.\r\nIn this proposal, the WEF nexus will be specially addressed from the point of view of resources to generate the\r\nnecessary knowledge to understand its complexity in Central Chile, and that will provide a timely transfer of the\r\nexisting connections to decision makers and society. The aim of this study will be to comprehend the recharge and\r\nconnection of surface and ground water in Central Chile and unravel their relationship with energy and food\r\nproduction. In this sense, the focus is on evaluating the hydrological cycle from mountain areas to the lowlands and\r\nevaluating the possibility that water resources can generate enough heat for direct geothermal projects. These\r\nresults, calculated based on real and current water data, will provide valuable information for the energy transition\r\nin Central Chile and will be an instrument to evaluate the real possibility of greenhouse gas reduction. Food\r\nproduction not only needs water but also to increase its resilience to extreme events (frost, heavy rains, etc.), so\r\nthe relationship between water availability, production per hectare, and geothermal energy (direct use) to stabilize\r\ncrop conditions will be explored.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> PVCAA3392-2022<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2022 - Agosto 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Funda\u00e7\u00e3o de Amparo \u00e0 Pesquisa e ao Desenvolvimento Cient\u00edfico e Tecnol\u00f3gico do Maranh\u00e3o - FAPEMA<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27014\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27014\" aria-expanded=\"false\" aria-controls=\"collapse-27014\">\n                                            Impacto da fertirriga\u00e7\u00e3o com sil\u00edcio e da inocula\u00e7\u00e3o com Azospirillum sobre os par\u00e2metros agron\u00f4micos, ecofisiol\u00f3gicos, produtivos e do valor nutricional do milho safrinha e\/ou sorgo e\/ou milheto para produ\u00e7\u00e3o de gr\u00e3os e silagens em dietas de ruminantes\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27014\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27014\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]A presente proposta \u00e9 um projeto de inova\u00e7\u00e3o no Brasil e tem como premissa\/meta de mostrar que \u00e9 poss\u00edvel diminuir N-fertilizante com o emprego de A. brasilense, como alternativa de FBN na tentativa de diminuir a fertiliza\u00e7\u00e3o qu\u00edmica, os altos custos de N-fertilizantes e consequentemente as deposi\u00e7\u00f5es de Nr nos ecossistemas, assim como melhorar a efici\u00eancia do uso da \u00e1gua a partir do emprego da fertirriga\u00e7\u00e3o com Si estabelecendo pela primeira vez as doses vi\u00e1veis agronomicamente, zootecnicamente e economicamente para o cultivo irrigado do milho safrinha e, na produ\u00e7\u00e3o de silagens na nutri\u00e7\u00e3o animal. Assim, ser\u00e1 avaliado os efeitos aditivos ou n\u00e3o, de diferentes doses de Si via fertirriga\u00e7\u00e3o e da inocula\u00e7\u00e3o ou n\u00e3o com A. brasiliense sobre: O ac\u00famulo e a efici\u00eancia de utiliza\u00e7\u00e3o dos nutrientes, em fun\u00e7\u00e3o do est\u00e1dio de desenvolvimento das plantas do milho; A estequiometria (rela\u00e7\u00f5es C:N:P:Si) e, o crescimento vegetativo do milho safrinha e\/ou sorgo e\/ou milheto; Os processos fisiol\u00f3gicos: taxa fotossint\u00e9tica, \u00edndice de cor verde, condut\u00e2ncia estom\u00e1tica, taxa de transpira\u00e7\u00e3o e efici\u00eancia de uso da \u00e1gua do milho e\/ou sorgo e\/ou milheto em estudo; As caracter\u00edsticas morfog\u00eanicas e estruturais, a din\u00e2mica de crescimento, a produ\u00e7\u00e3o e quantifica\u00e7\u00e3o de biomassa a\u00e9rea, a composi\u00e7\u00e3o qu\u00edmico-bromatol\u00f3gica da biomassa, a produ\u00e7\u00e3o e sanidade dos gr\u00e3os, o \u00edndice de colheita de gr\u00e3os e a efici\u00eancia agron\u00f4mica do milho e\/ou sorgo e\/ou milheto; Al\u00e9m de avaliar o perfil fermentativo, a estabilidade aer\u00f3bia, a composi\u00e7\u00e3o qu\u00edmica e a digestibilidade in vitro das silagens na forma tradicional e, na forma de ra\u00e7\u00e3o total para dietas de bovinos de corte e\/ou cabras leiteiras[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26055\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Influencia de factores ambientales y productivos sobre las comunidades microbianas en ganader\u00edas de caprino lechero en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26055\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26055\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetivo general de la propuesta es caracterizar las comunidades microbianas presentes en las ganader\u00edas de caprino lechero, su variaci\u00f3n estacional, la influencia de los factores ambientales y productivos asociados con su presencia y distribuci\u00f3n. Para su consecuci\u00f3n, se han planteado los siguientes objetivos:\r\n- Evaluaci\u00f3n de la microbiolog\u00eda ambiental de las ganader\u00edas y su relaci\u00f3n con la calidad microbiol\u00f3gica de la leche de tanque.\r\n- Identificaci\u00f3n de los factores ambientales y productivos que afectan a la calidad de la leche de las ganader\u00edas caprinas.\r\n- Estudio de la diversidad gen\u00e9tica de microorganismos de inter\u00e9s para la elaboraci\u00f3n de queso presentes en el ambiente.\r\n- An\u00e1lisis sensorial de los quesos elaborados en las ganader\u00edas caprinas.\r\n- Elaboraci\u00f3n de un manual de Buenas Pr\u00e1cticas Ganaderas para optimizar las actuaciones encaminadas a mejorar la calidad de la leche de tanque y de los productos l\u00e1cteos.\r\nEstos objetivos se abordar\u00e1n mediante el estudio de la presencia de distintos microorganismos (recuento de mes\u00f3filos totales, bacterias \u00e1cido-l\u00e1cticas, levaduras, mohos, estafilococos y microorganismos especulados) en el ambiente de la sala de orde\u00f1o y de los alojamientos de las cabras de orde\u00f1o, en la alimentaci\u00f3n, en la superficie de los pezones de las cabras y en la propia leche de tanque, y su relaci\u00f3n con distintos factores asociados al ambiente y al sistema productivo de las ganader\u00edas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Patrocinante<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> CIES005<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2022 - Julio 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25998\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Caracterizaci\u00f3n de la capacidad funcional  y condici\u00f3n f\u00edsica de personas mayores de siete comunas de la zona centro-sur de Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25998\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25998\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]mayores (PM) de 65 a\u00f1os superan el n\u00famero de menores de 5 a\u00f1os y se espera que para el a\u00f1o 2030 \u00e9sta cifra aumente en un 34%. Frente a esto, Chile tiene importantes desaf\u00edos orientados al desarrollo de estrategias que promuevan el envejecimiento activo y saludable. Se acepta que una buena condici\u00f3n f\u00edsica se relaciona con una mejor capacidad funcional y reducci\u00f3n de la mortalidad en PM. Si bien existen estudios de cohortes de PM en Chile como ALEXANDROS, n= 2311 y la encuesta nacional de calidad de vida en la vejez  (n=2.132), estas no est\u00e1n espec\u00edficamente orientadas a la evaluaci\u00f3n de la condici\u00f3n f\u00edsica y su relaci\u00f3n con la capacidad funcional de las personas y, adem\u00e1s, son cohortes pertenecientes principalmente a la Regi\u00f3n Metropolitana. \r\nEl prop\u00f3sito de este proyecto es caracterizar la condici\u00f3n f\u00edsica y capacidad funcional de personas mayores de siete diferentes comunas de la zona centro-sur de Chile y su relaci\u00f3n con caracter\u00edsticas bio-demogr\u00e1ficas, de manera que permita orientar pol\u00edticas y acciones necesarias e integrales para la mejora de estos par\u00e1metros considerados determinantes del envejecimiento activo y saludable. Adicionalmente, se espera iniciar una cohorte multi-regional para estudios longitudinales, como tambi\u00e9n, el inicio de un biobanco para futuros an\u00e1lisis de biomarcadores relacionados a sarcopenia, condici\u00f3n f\u00edsica y capacidad funcional.\r\nSe propone un dise\u00f1o transversal, en donde se incluir\u00e1n PM de 60 a\u00f1os y m\u00e1s,  capaces de caminar sin ayuda de otra persona al menos una distancia de 10 metros, pertenecientes a centros de Atenci\u00f3n Primaria o centros comunitarios de 7 comunas: Valpara\u00edso, Santiago, Rancagua, Talca, Chill\u00e1n, Temuco y Puerto Montt. Se excluir\u00e1n personas que presenten deterioro cognitivo, patolog\u00edas card\u00edacas, respiratorias, m\u00fasculo esquel\u00e9ticas o neurol\u00f3gicas que le impidan o tengan contraindicaci\u00f3n para realizar las evaluaciones o pruebas de rendimiento f\u00edsico, incapacidad para comunicarse o dependencia en las actividades b\u00e1sicas de la vida diaria seg\u00fan \u00cdndice de Barthel. \r\nEl tama\u00f1o muestral se ha estimado a partir de la poblaci\u00f3n total compuesta por el total de sujetos de las 7 comunas (279.991), utilizando los siguientes par\u00e1metros: N=total poblacional, Z2=3,84 (nivel de confianza 95%), p=prevalencia de sarcopenia (19,1%), p=1-p y d2=3% precisi\u00f3n o error de muestreo. La muestra calculada se ajust\u00f3 a un 30% de p\u00e9rdidas por lo que tama\u00f1o de muestra fue de 936 en total. La muestra ser\u00e1 seleccionada mediante muestreo aleatorio simple. \r\nSe  caracterizar\u00e1n antecedentes biodemogr\u00e1ficos, de salud,  capacidad funcional y condici\u00f3n f\u00edsica de las PM, a trav\u00e9s de la aplicaci\u00f3n de cuestionarios,  pruebas de condici\u00f3n f\u00edsica y test funcionales, todos validados y estandarizados en cada lugar de evaluaci\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> CIES005<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2022 - Julio 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26139\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Caracterizaci\u00f3n de la capacidad funcional  y condici\u00f3n f\u00edsica de personas mayores de siete comunas de la zona centro-sur de Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26139\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26139\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]mayores (PM) de 65 a\u00f1os superan el n\u00famero de menores de 5 a\u00f1os y se espera que para el a\u00f1o 2030 \u00e9sta cifra aumente en un 34%. Frente a esto, Chile tiene importantes desaf\u00edos orientados al desarrollo de estrategias que promuevan el envejecimiento activo y saludable. Se acepta que una buena condici\u00f3n f\u00edsica se relaciona con una mejor capacidad funcional y reducci\u00f3n de la mortalidad en PM. Si bien existen estudios de cohortes de PM en Chile como ALEXANDROS, n= 2311 y la encuesta nacional de calidad de vida en la vejez  (n=2.132), estas no est\u00e1n espec\u00edficamente orientadas a la evaluaci\u00f3n de la condici\u00f3n f\u00edsica y su relaci\u00f3n con la capacidad funcional de las personas y, adem\u00e1s, son cohortes pertenecientes principalmente a la Regi\u00f3n Metropolitana. \r\nEl prop\u00f3sito de este proyecto es caracterizar la condici\u00f3n f\u00edsica y capacidad funcional de personas mayores de siete diferentes comunas de la zona centro-sur de Chile y su relaci\u00f3n con caracter\u00edsticas bio-demogr\u00e1ficas, de manera que permita orientar pol\u00edticas y acciones necesarias e integrales para la mejora de estos par\u00e1metros considerados determinantes del envejecimiento activo y saludable. Adicionalmente, se espera iniciar una cohorte multi-regional para estudios longitudinales, como tambi\u00e9n, el inicio de un biobanco para futuros an\u00e1lisis de biomarcadores relacionados a sarcopenia, condici\u00f3n f\u00edsica y capacidad funcional.\r\nSe propone un dise\u00f1o transversal, en donde se incluir\u00e1n PM de 60 a\u00f1os y m\u00e1s,  capaces de caminar sin ayuda de otra persona al menos una distancia de 10 metros, pertenecientes a centros de Atenci\u00f3n Primaria o centros comunitarios de 7 comunas: Valpara\u00edso, Santiago, Rancagua, Talca, Chill\u00e1n, Temuco y Puerto Montt. Se excluir\u00e1n personas que presenten deterioro cognitivo, patolog\u00edas card\u00edacas, respiratorias, m\u00fasculo esquel\u00e9ticas o neurol\u00f3gicas que le impidan o tengan contraindicaci\u00f3n para realizar las evaluaciones o pruebas de rendimiento f\u00edsico, incapacidad para comunicarse o dependencia en las actividades b\u00e1sicas de la vida diaria seg\u00fan \u00cdndice de Barthel. \r\nEl tama\u00f1o muestral se ha estimado a partir de la poblaci\u00f3n total compuesta por el total de sujetos de las 7 comunas (279.991), utilizando los siguientes par\u00e1metros: N=total poblacional, Z2=3,84 (nivel de confianza 95%), p=prevalencia de sarcopenia (19,1%), p=1-p y d2=3% precisi\u00f3n o error de muestreo. La muestra calculada se ajust\u00f3 a un 30% de p\u00e9rdidas por lo que tama\u00f1o de muestra fue de 936 en total. La muestra ser\u00e1 seleccionada mediante muestreo aleatorio simple. \r\nSe  caracterizar\u00e1n antecedentes biodemogr\u00e1ficos, de salud,  capacidad funcional y condici\u00f3n f\u00edsica de las PM, a trav\u00e9s de la aplicaci\u00f3n de cuestionarios,  pruebas de condici\u00f3n f\u00edsica y test funcionales, todos validados y estandarizados en cada lugar de evaluaci\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2022 - Septiembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26262\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Sistema biotecnol\u00f3gico de extracci\u00f3n de tierras raras presentes en relaves mineros.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26262\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26262\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La pol\u00edtica minera 2050 exige al sector el desarrollo de tecnolog\u00edas sustentables y amigables con\r\nel medio ambiente para la explotaci\u00f3n de nuevos minerales de inter\u00e9s comercial. En este contexto, los\r\nlineamientos nacionales apuntan a que Chile se convierta en unos de los principales exportadores de\r\ntierras raras, compuestas por elementos que se encuentran en muy baja concentraci\u00f3n en la corteza\r\nterrestre los cuales presentan una variedad importante de usos con un alto valor comercial.\r\nAl respecto, el relave Cauquenes dentro de la regi\u00f3n de O\u0092Higgins, se presenta como una\r\nexcelente alternativa para la extracci\u00f3n de tierras raras, dada la alta concentraci\u00f3n de Cerio, Lantano,\r\nNeodimio e Itrio, elementos hasta 15 veces m\u00e1s caros que el cobre, necesarios para la producci\u00f3n de\r\nbater\u00edas, catalizadores, imanes, radares, semiconductores, entre otros.\r\nEntendiendo que, Chile cuenta a nivel nacional con m\u00e1s de 750 relaves, la extracci\u00f3n de tierras\r\nraras da cuenta de una oportunidad \u00fanica para el levantamiento de proyectos interdisciplinarios con\r\nenfoque comercial en todo el pa\u00eds, perfectamente alineados con las pol\u00edticas mineras nacionales. Al\r\nrespecto, la biotecnolog\u00eda se ha posicionado eficientemente como una alternativa real para el desarrollo\r\nde tecnolog\u00edas aplicables a la miner\u00eda. Recientemente se han descrito una serie de especies bacterianas\r\ncapaces de realizar el proceso de Biolixiviaci\u00f3n de tierras raras, el cual consiste en la solubilizaci\u00f3n de\r\nminerales complejos permitiendo posteriormente la extracci\u00f3n de forma eficiente de los elementos de\r\ninter\u00e9s. Esta extracci\u00f3n puede llevarse a cabo a trav\u00e9s del uso de plantas, proceso denominado\r\nFitoextracci\u00f3n. Literatura reciente declara que especies de sauce (Salix spp) tienen la capacidad de extraer\r\ny acumular con gran eficiencia diferentes tierras raras, sistema que puede complementarse\r\nperfectamente con el proceso de Biolixiviaci\u00f3n haciendo eficiente en terreno la obtenci\u00f3n de los\r\nelementos raros de gran valor comercial.\r\nCon una fuerte colaboraci\u00f3n con la empresa Minera Valle Central, nuestro grupo de investigaci\u00f3n\r\na trav\u00e9s del financiamiento del proyecto interdisciplinario UOH versi\u00f3n 1, logr\u00f3 caracterizar parte\r\nimportante de la biodiversidad de microorganismos y plantas presentes en el relave Cauquenes. Este\r\nestudio nos permiti\u00f3 identificar bacterias con un alto potencial para biolixiviar tierras raras, entre ellos los\r\ncuatro elementos raros altamente concentrados en el relave (trabajo publicado). Adicionalmente,\r\nlogramos determinar la capacidad inicial de especies de sauce para extraer y acumular Neodimio y\r\nLantano (trabajo en preparaci\u00f3n). Todos estos resultados abren una oportunidad \u00fanica de colaboraci\u00f3n\r\ninterdisciplinaria enfocada al desarrollo de un sistema biotecnol\u00f3gico combinado entre bacterias y plantas\r\npara la extracci\u00f3n y acumulaci\u00f3n eficiente de tierras raras, objetivo central de la presente propuesta de\r\ninvestigaci\u00f3n.\r\nDentro de un per\u00edodo de dos a\u00f1os, a trav\u00e9s de diferentes ensayos microbiol\u00f3gicos\r\ncaracterizaremos al menos cinco especies bacterianas capaces biolixiviar Cerio, Lantano, Neodimio e Itrio.\r\nEn paralelo, se cultivar\u00e1n en el laboratorio plantas de sauce provenientes del relave Cauquenes, las cuales\r\nse seleccionar\u00e1n en base a su tasa de crecimiento y capacidad de extraer y acumular estos elementos. El\r\nsiguiente paso consiste a nivel piloto de laboratorio, ajustar la combinaci\u00f3n de bacterias y plantas con el\r\nmejor rendimiento de extracci\u00f3n, para finalmente realizar pruebas en terreno directamente en el relave\r\nCauquenes.\r\nEn esta nueva etapa, nuevamente contamos con el apoyo de Minera Valle Central, el centro Basal\r\nCMM, el Instituto Milenio CRG, sumado a la colaboraci\u00f3n activa de otros laboratorios e institutos\r\ninternacionales. Adicionalmente, participar\u00e1n de esta propuesta nuevos acad\u00e9micos de la UOH, del ICA3\r\nla Dra. Carolina \u00c1lvarez y del ICI el Dr. Domingo Jullian, quienes llevar\u00e1n a cabo parte importante de la\r\ninvestigaci\u00f3n aportando con sus conocimientos y capacidades de laboratorio, aumentando el grupo de\r\ninvestigadores con vistas de postulaciones futuras a proyectos de mayor envergadura, desarrollo de\r\nart\u00edculos y realizaci\u00f3n de tesis conjuntas. En resumen, pretendemos consolidar la l\u00ednea de investigaci\u00f3n\r\ninterdisciplinaria previamente apoyada en el concurso anterior, proyectando en esta nueva etapa\r\nlineamientos hacia un foco comercial, generando resultados y datos necesarios para el levantamiento de\r\npostulaciones a concursos de innovaci\u00f3n y desarrollo, tales como FIC, CORFO y FONDEF. Finalmente,\r\ncomprometemos mantener la tasa de publicaciones, actividades de difusi\u00f3n, formaci\u00f3n de capital\r\nhumano y fortalecimiento de puentes de colaboraci\u00f3n con otras universidades nacionales e\r\ninternacionales, sumado al fuerte compromiso regional y principalmente, consolidar el v\u00ednculo con\r\nempresas del rubro minero.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2022 - Septiembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26391\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Sistema biotecnol\u00f3gico de extracci\u00f3n de tierras raras presentes en relaves mineros.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26391\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26391\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La pol\u00edtica minera 2050 exige al sector el desarrollo de tecnolog\u00edas sustentables y amigables con\r\nel medio ambiente para la explotaci\u00f3n de nuevos minerales de inter\u00e9s comercial. En este contexto, los\r\nlineamientos nacionales apuntan a que Chile se convierta en unos de los principales exportadores de\r\ntierras raras, compuestas por elementos que se encuentran en muy baja concentraci\u00f3n en la corteza\r\nterrestre los cuales presentan una variedad importante de usos con un alto valor comercial.\r\nAl respecto, el relave Cauquenes dentro de la regi\u00f3n de O\u0092Higgins, se presenta como una\r\nexcelente alternativa para la extracci\u00f3n de tierras raras, dada la alta concentraci\u00f3n de Cerio, Lantano,\r\nNeodimio e Itrio, elementos hasta 15 veces m\u00e1s caros que el cobre, necesarios para la producci\u00f3n de\r\nbater\u00edas, catalizadores, imanes, radares, semiconductores, entre otros.\r\nEntendiendo que, Chile cuenta a nivel nacional con m\u00e1s de 750 relaves, la extracci\u00f3n de tierras\r\nraras da cuenta de una oportunidad \u00fanica para el levantamiento de proyectos interdisciplinarios con\r\nenfoque comercial en todo el pa\u00eds, perfectamente alineados con las pol\u00edticas mineras nacionales. Al\r\nrespecto, la biotecnolog\u00eda se ha posicionado eficientemente como una alternativa real para el desarrollo\r\nde tecnolog\u00edas aplicables a la miner\u00eda. Recientemente se han descrito una serie de especies bacterianas\r\ncapaces de realizar el proceso de Biolixiviaci\u00f3n de tierras raras, el cual consiste en la solubilizaci\u00f3n de\r\nminerales complejos permitiendo posteriormente la extracci\u00f3n de forma eficiente de los elementos de\r\ninter\u00e9s. Esta extracci\u00f3n puede llevarse a cabo a trav\u00e9s del uso de plantas, proceso denominado\r\nFitoextracci\u00f3n. Literatura reciente declara que especies de sauce (Salix spp) tienen la capacidad de extraer\r\ny acumular con gran eficiencia diferentes tierras raras, sistema que puede complementarse\r\nperfectamente con el proceso de Biolixiviaci\u00f3n haciendo eficiente en terreno la obtenci\u00f3n de los\r\nelementos raros de gran valor comercial.\r\nCon una fuerte colaboraci\u00f3n con la empresa Minera Valle Central, nuestro grupo de investigaci\u00f3n\r\na trav\u00e9s del financiamiento del proyecto interdisciplinario UOH versi\u00f3n 1, logr\u00f3 caracterizar parte\r\nimportante de la biodiversidad de microorganismos y plantas presentes en el relave Cauquenes. Este\r\nestudio nos permiti\u00f3 identificar bacterias con un alto potencial para biolixiviar tierras raras, entre ellos los\r\ncuatro elementos raros altamente concentrados en el relave (trabajo publicado). Adicionalmente,\r\nlogramos determinar la capacidad inicial de especies de sauce para extraer y acumular Neodimio y\r\nLantano (trabajo en preparaci\u00f3n). Todos estos resultados abren una oportunidad \u00fanica de colaboraci\u00f3n\r\ninterdisciplinaria enfocada al desarrollo de un sistema biotecnol\u00f3gico combinado entre bacterias y plantas\r\npara la extracci\u00f3n y acumulaci\u00f3n eficiente de tierras raras, objetivo central de la presente propuesta de\r\ninvestigaci\u00f3n.\r\nDentro de un per\u00edodo de dos a\u00f1os, a trav\u00e9s de diferentes ensayos microbiol\u00f3gicos\r\ncaracterizaremos al menos cinco especies bacterianas capaces biolixiviar Cerio, Lantano, Neodimio e Itrio.\r\nEn paralelo, se cultivar\u00e1n en el laboratorio plantas de sauce provenientes del relave Cauquenes, las cuales\r\nse seleccionar\u00e1n en base a su tasa de crecimiento y capacidad de extraer y acumular estos elementos. El\r\nsiguiente paso consiste a nivel piloto de laboratorio, ajustar la combinaci\u00f3n de bacterias y plantas con el\r\nmejor rendimiento de extracci\u00f3n, para finalmente realizar pruebas en terreno directamente en el relave\r\nCauquenes.\r\nEn esta nueva etapa, nuevamente contamos con el apoyo de Minera Valle Central, el centro Basal\r\nCMM, el Instituto Milenio CRG, sumado a la colaboraci\u00f3n activa de otros laboratorios e institutos\r\ninternacionales. Adicionalmente, participar\u00e1n de esta propuesta nuevos acad\u00e9micos de la UOH, del ICA3\r\nla Dra. Carolina \u00c1lvarez y del ICI el Dr. Domingo Jullian, quienes llevar\u00e1n a cabo parte importante de la\r\ninvestigaci\u00f3n aportando con sus conocimientos y capacidades de laboratorio, aumentando el grupo de\r\ninvestigadores con vistas de postulaciones futuras a proyectos de mayor envergadura, desarrollo de\r\nart\u00edculos y realizaci\u00f3n de tesis conjuntas. En resumen, pretendemos consolidar la l\u00ednea de investigaci\u00f3n\r\ninterdisciplinaria previamente apoyada en el concurso anterior, proyectando en esta nueva etapa\r\nlineamientos hacia un foco comercial, generando resultados y datos necesarios para el levantamiento de\r\npostulaciones a concursos de innovaci\u00f3n y desarrollo, tales como FIC, CORFO y FONDEF. Finalmente,\r\ncomprometemos mantener la tasa de publicaciones, actividades de difusi\u00f3n, formaci\u00f3n de capital\r\nhumano y fortalecimiento de puentes de colaboraci\u00f3n con otras universidades nacionales e\r\ninternacionales, sumado al fuerte compromiso regional y principalmente, consolidar el v\u00ednculo con\r\nempresas del rubro minero.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2022 - Marzo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26622\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Towards omics-assisted breeding of Eucalyptus essential oils, and insights into transcriptional regulation of terpenoid genes in response to water deficit\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26622\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26622\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]NA[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2022 - Septiembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26740\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Cohesi\u00f3n Social e Inversi\u00f3n Ideol\u00f3gica: construcci\u00f3n de mayor\u00edas sociales y pol\u00edticas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26740\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26740\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto busca analizar la manera en que las personas hacen juicios ideol\u00f3gicos sobre distintos temas sociales contigentes en Chile, a lo largo del tiempo.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26941\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            An\u00e1lisis multi-\u00f3mico de cultivares de almendro (Prunus dulcis L.) con fenotipos contrastantes en respuesta a estr\u00e9s h\u00eddrico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26941\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26941\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La regi\u00f3n de O'Higgins, cuya principal actividad econ\u00f3mica corresponde a la agricultura,\r\nest\u00e1 siendo\r\nseveramente afectada por la sequ\u00eda como consecuencia del cambio clim\u00e1tico, generando impactos\r\nnegativos para este sector productivo . As\u00ed, la b\u00fasqueda de especies y\/o cultivares con mayor tolerancia\r\nal estr\u00e9s h\u00eddrico es clave para diversificar l a matriz productiva de la regi\u00f3n. El almendro es una opci\u00f3n\r\nviable para la regi\u00f3n debido a su ampliamente reportada tolerancia al estr\u00e9s h\u00eddrico, con gran \u00e9xito en el\r\ncultivo de esta especie en \u00e1reas con clima Mediterr\u00e1neo, incluyendo Chile, por lo que la identificaci\u00f3n de\r\ncultivares con mayor tolerancia a este estr\u00e9s es de importancia.\r\nA nivel fisiol\u00f3gico, el principal efecto del estr\u00e9s h\u00eddrico es el cierre estom\u00e1tico, con el objetivo de evitar\r\nuna disminuci\u00f3n dr\u00e1stica en el estado h\u00eddrico de la planta (p otencial h\u00eddrico, &#936; L ), esto disminuye la\r\nasimilaci\u00f3n de carbono y por consiguiente la producci\u00f3n. Sin embargo, especies y cultivares han\r\ndesarrollado distintas estrategias para responder frente al estr\u00e9s h\u00eddrico, lo que se ha descrito a trav\u00e9s de\r\nlos compo rtamientos isoh\u00eddricos y anisoh\u00eddricos. En breve, especies\/cultivares con comportamiento\r\nisoh\u00eddrico se caracterizan por un r\u00e1pido cierre estom\u00e1tico frente al estr\u00e9s h\u00eddrico previniendo as\u00ed ca\u00eddas\r\ndr\u00e1sticas en &#936; L . Por el contrario, especies\/cultivares aniso h\u00eddricos mantienen la apertura estom\u00e1tica\r\ndurante el estr\u00e9s, permitiendo una ca\u00edda en &#936; L y, por lo tanto, sosteniendo la asimilaci\u00f3n de carbono. En\r\nconsecuencia, el comportamiento anisoh\u00eddrico se asocia a mayores tasas fotosint\u00e9ticas y eficiencia de uso\r\nde agua a pesar de la escasez h\u00eddrica. La caracterizaci\u00f3n e identificaci\u00f3n de genotipos anisoh\u00eddricos es\r\nimportante para optimizar la b\u00fasqueda de nuevos cultivares a ser producidos en la regi\u00f3n de O'Higgins,\r\nespecialmente en el secano interior donde los efec tos del d\u00e9ficit h\u00eddrico son m\u00e1s severos. Como parte\r\ndel desarrollo del proyecto Fondecyt de iniciaci\u00f3n de la Dra. Alvarez, se han identificado y caracterizado\r\na nivel fisiol\u00f3gico tres cultivares de almendro con comportamiento an\/isoh\u00eddricos contrastantes: Avijor,\r\nIsabelona y Soleta. Si bien el proyecto anteriormente descrito incluye el an\u00e1lisis transcripcional de algunos\r\ngenes, que hipot\u00e9ticamente tendr\u00edan un rol en la diferenciaci\u00f3n entre ambos comportamientos, este\r\nan\u00e1lisis puntual no permitir\u00eda comprende r en profundidad los mecanismos moleculares y rutas que\r\nsubyacen procesos adaptativos y respuestas a se\u00f1ales ambientales a nivel de genoma completo. Para\r\nahondar en esto \u00faltimo, hemos planteado el siguiente objetivo general: \u0093 Determinar las diferencias\r\ngen \u00f3micas, epigen\u00e9ticas y transcript\u00f3micas que determinan el fenotipo anisoh\u00eddrico e isoh\u00eddrico entre\r\ndistintos cultivares de almendro durante el estr\u00e9s de d\u00e9ficit h\u00eddrico\u0094 h\u00eddrico\u0094.\r\nSin embargo, a la fecha solamente tres variedades de almendro han sido secuenciadas\r\n: Nonpareil, Texas\r\ny Lauranne. Si bien el genoma de esta especie es peque\u00f1o (~250Mb) su alto nivel de heterocigosidad\r\ndificulta su ensamble. Espec\u00edficamente para esta especie, abordaremos la secuenciaci\u00f3n del genoma con\r\nuna estrategia h\u00edbrida que integra d atos de Oxford Nanopore (para secuencias largas) y MGI (lecturas\r\ncortas) y algoritmos desarrollados por el Dr. Di Genova que permitir\u00e1n realizar construcciones a escala\r\ncromos\u00f3mica para las tres variedades propuestas. Los genomas ensamblados permitir\u00e1n det erminar\r\nvariantes gen\u00e9ticas y patrones epigen\u00e9ticos diferenciales entre los tres cultivares propuestos.\r\nAdicionalmente, secuenciaremos y analizaremos datos de expresi\u00f3n g\u00e9nica de las tres variedades\r\nenfrentadas a estr\u00e9s h\u00eddrico, lo que nos permitir\u00e1 estudi ar por primera vez el impacto funcional de\r\nvariantes gen\u00e9ticas y epigen\u00e9ticas asociados al estr\u00e9s h\u00eddrico.\r\nEn resumen, nuestro proyecto multidisciplinario generar\u00e1 el genoma de referencia y epigenoma para los\r\ntres cultivares: Avijor, Isabelona y Soleta. A dicionalmente, realizaremos un primer mapeo a nivel\r\ngen\u00f3mico, epigen\u00e9tico y de expresi\u00f3n de los mecanismos y programas moleculares durante el estr\u00e9s\r\nh\u00eddrico de los tres cultivares de almendro.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>COES<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26985\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Entre el cumplimiento y la resistencia: \u00bfC\u00f3mo se posiciona la ciudadan\u00eda frente a la polic\u00eda en Chile?\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26985\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26985\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Materia Espec\u00edfica: El proyecto busca comprender hasta qu\u00e9 punto los individuos legitiman, y las maneras en las que se posicionan frente a la polic\u00eda en Chile.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2022 - Septiembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26208\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Investigaci\u00f3n interdisciplinaria del desarrollo de competencias profesionales en estudiantes de Ingenier\u00eda Civil Mec\u00e1nica de la UOH\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26208\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26208\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetivo de la presente propuesta es investigar el desarrollo de competencias profesionales de\r\nestudiantes UOH de Ingenier\u00eda Civil Mec\u00e1nica a trav\u00e9s de acciones de intervenci\u00f3n mediante dise\u00f1o \u00e1gil\r\ny fabricaci\u00f3n e investigaci\u00f3n mediante t\u00e9cnicas de psicolog\u00eda cognitiva y an\u00e1lisis de contenido.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2022 - Diciembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>FECI - Par Explora<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26853\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            AquaRocks\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26853\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26853\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El agua subterr\u00e1nea es una fuente clave para nuestra supervivencia. \u00c9sta se almacena en\r\nformaciones geol\u00f3gicas compuestas por rocas de diferentes propiedades llamadas acu\u00edferos. El\r\ncambio clim\u00e1tico puede reducir la disponibilidad de estas aguas subterr\u00e1neas minando las\r\nreservas de los acu\u00edferos.\r\nEl presente proyecto tiene como fin realizar actividades para concientizar y promover el\r\nconocimiento de los acu\u00edferos, y c\u00f3mo \u00e9stos interact\u00faan con el medio dependiendo de las\r\npropiedades de la roca o minerales presentes en la zona. Para ello, se desarrollar\u00e1 una\r\naplicaci\u00f3n m\u00f3vil como herramienta de identificaci\u00f3n de rocas y minerales, donde cada muestra\r\nestar\u00e1 descrita incluyendo informaci\u00f3n de sus propiedades (composici\u00f3n, porosidad, etc.), con\r\nun modelo 3D de la muestra vinculada al tipo de acu\u00edfero. Esta app ser\u00e1 presentada en\r\nactividades de divulgaci\u00f3n donde se mostrar\u00e1n los distintos tipos de acu\u00edferos, las rocas que los\r\nforman y c\u00f3mo los minerales pueden actuar como contaminantes naturales en ellos. La\r\naplicaci\u00f3n ser\u00e1 testeada con una instituci\u00f3n de educaci\u00f3n asociada y se pretende pueda ser\r\nparte del patrimonio tecnol\u00f3gico de la UOH.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2022 - Septiembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26878\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Investigaci\u00f3n interdisciplinaria del desarrollo de competencias profesionales en estudiantes de Ingenier\u00eda Civil Mec\u00e1nica de la UOH\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26878\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26878\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetivo de la presente propuesta es investigar el desarrollo de competencias profesionales de\r\nestudiantes UOH de Ingenier\u00eda Civil Mec\u00e1nica a trav\u00e9s de acciones de intervenci\u00f3n mediante dise\u00f1o \u00e1gil\r\ny fabricaci\u00f3n e investigaci\u00f3n mediante t\u00e9cnicas de psicolog\u00eda cognitiva y an\u00e1lisis de contenido.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> NCS2022_039<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2022 - Octubre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26953\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            N\u00facleo Milenio de estudios de discapacidad y ciudadania\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26953\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26953\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]l N\u00facleo Milenio Discapacidad y Ciudadan\u00eda (DISCA) es un centro de investigaci\u00f3n interdisciplinario financiado por la Agencia Nacional de Investigaci\u00f3n y Desarrollo (2023 a 2025).\r\n\r\nCon un abordaje multi y transdisciplinario, la agenda de DISCA se centra en el estudio de los procesos y mecanismos a trav\u00e9s de los cuales las personas con discapacidad se transforman en ciudadanas.\r\n\r\nDISCA est\u00e1 dirigido por una persona con discapacidad, cuenta con un consejo de expertas y expertos por experiencia y esta alineado con los principios de la investigaci\u00f3n inclusiva y participativa. Sus investigadores, pioneros en la investigaci\u00f3n en discapacidad en el pa\u00eds, utilizan metodolog\u00edas mixtas, cuantitativas y cualitativas, integrando conocimientos de la antropolog\u00eda social, el derecho, la salud, la econom\u00eda, la sociolog\u00eda y la psicolog\u00eda, en conjunto con el campo transdisciplinario de los estudios de la discapacidad.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2022 - Septiembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26232\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estrategias para el fortalecimiento de la adquisici\u00f3n y la resistencia a la extinci\u00f3n de la aversi\u00f3n condicionada al sabor de hojas de frutales en ovinos para la explotaci\u00f3n sostenible de sistemas agropecuarios.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26232\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26232\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La asociaci\u00f3n de las claves sensoriales con consecuencias negativas orales o post-ingestivas tras el consumo de un alimento genera, en futuras presentaciones, el rechazo por dichas claves sensoriales. Este mecanismo evolutivo de aprendizaje asociativo, denominado aversi\u00f3n condicionada al sabor, tiene el valor funcional de prevenir posibles intoxicaciones. La aversi\u00f3n condicionada al sabor tiene la particularidad de ser una forma de aprendizaje r\u00e1pida siendo a veces suficiente un solo evento de asociaci\u00f3n para generar la aversi\u00f3n si los est\u00edmulos son novedosos. Como procedimiento, la aversi\u00f3n condicionada al sabor es utilizada muy extensamente en investigaci\u00f3n b\u00e1sica en psicolog\u00eda experimental y comparada, y de forma aplicada en esta y otras disciplinas. Experiencias de aversi\u00f3n condicionada en ovinos y caprinos han permitido generar sistemas de pastoreo en explotaciones de frutales con el fin de desmalezar el terreno sin consumir la hoja o brotes de los arboles productivos, evitando con ello el uso de pesticidas. En estos estudios se presenta la hoja que se busca proteger para que el animal la consuma, seguida de la administraci\u00f3n de LiCl, lo cual genera malestar gastrointestinal y como resultado, el rechazo selectivo de este alimento por parte de los animales prefiriendo el consumo de la maleza que se encuentra alrededor de los cultivos. El cultivo de frutales supone una de las actividades econ\u00f3micas m\u00e1s importantes de la Regi\u00f3n de O'Higgins, por lo que el uso de estrategias agropecuarias sostenibles mediante el establecimiento de aversi\u00f3n condicionada podr\u00eda ser de gran inter\u00e9s para la regi\u00f3n. Resultados no publicados de aversiones condicionadas para el control de malezas en vi\u00f1as y otras producciones agr\u00edcolas en Chile han sido auspiciosos. Sin embargo, la aversi\u00f3n condicionada a las hojas de los frutales no ha resultado ser persistente en el tiempo. Una aversi\u00f3n inestable y poco duradera supondr\u00eda un riesgo para los agricultores, que podr\u00edan ver malogrados sus cultivos si los animales comenzaran a elegirlos como alimento. La investigaci\u00f3n b\u00e1sica en psicolog\u00eda del aprendizaje ha aportado conocimiento \u00fatil para dise\u00f1ar estrategias dirigidas a fortalecer aversiones condicionadas. Por ejemplo, aunque existe poca informaci\u00f3n al respecto, el aprendizaje o condicionamiento prenatal y el aprendizaje observacional podr\u00edan jugar un papel importante a la hora fortalecer aprendizajes por condicionamiento cl\u00e1sico. El objetivo del presente proyecto es estudiar el efecto del aprendizaje prenatal y del aprendizaje social-observacional en la adquisici\u00f3n y la extinci\u00f3n de aversi\u00f3n condicionada a hojas de frutales en ovinos, a fin de implementar un sistema eficaz, sostenible y org\u00e1nico de explotaci\u00f3n agropecuaria en la Regi\u00f3n de O'Higgins. Un total de 48 ovejas adultas en gestaci\u00f3n temprana y sus cr\u00edas ser\u00e1n utilizados con el fin de estudiar el efecto del aprendizaje prenatal y social sobre la adquisici\u00f3n y resistencia a la extinci\u00f3n de aversiones condicionadas. Para esto se realizar\u00e1 un dise\u00f1o factorial de 2x2 en donde ovejas en gestaci\u00f3n tard\u00eda se someter\u00e1n (n24) o no (n24) a aversi\u00f3n condicionada asociando hojas de frutales con LiCL. La mitad de los corderos de cada grupo observaran a sus madres durante la conducta de consumo. Posteriormente los corderos de cada grupo se someter\u00e1n tras el destete a aversi\u00f3n condicionada de manera directa asociando las mismas hojas de frutales con LiCl. Se cuantificar\u00e1 el periodo de extinci\u00f3n de la aversi\u00f3n condicionada en cada cordero, analizando el consumo y palatabilidad percibida por las hojas. En tanto que el cultivo de frutales, as\u00ed como la explotaci\u00f3n ganadera son actividades econ\u00f3micas muy relevantes en la regi\u00f3n de O\u0092Higgins el \u00e9xito del proyecto podr\u00eda ser relevante para su desarrollo sostenible; 1) posibilitando la comercializaci\u00f3n de productos agr\u00edcolas org\u00e1nicos, libres de pesticidas y 2) permitiendo la nutrici\u00f3n de ganado ovino frente a una crisis h\u00eddrica que cada vez hace m\u00e1s escaso el acceso a forraje fresco. El conocimiento generado a partir de la colaboraci\u00f3n del \u00e1rea de ciencia animal y de psicolog\u00eda comparada abre una gran oportunidad para el desarrollo de ciencia b\u00e1sica y aplicada en nuestra regi\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2022 - Septiembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26732\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estrategias para el fortalecimiento de la adquisici\u00f3n y la resistencia a la extinci\u00f3n de la aversi\u00f3n condicionada al sabor de hojas de frutales en ovinos para la explotaci\u00f3n sostenible de sistemas agropecuarios.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26732\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26732\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La asociaci\u00f3n de las claves sensoriales con consecuencias negativas orales o post-ingestivas tras el consumo de un alimento genera, en futuras presentaciones, el rechazo por dichas claves sensoriales. Este mecanismo evolutivo de aprendizaje asociativo, denominado aversi\u00f3n condicionada al sabor, tiene el valor funcional de prevenir posibles intoxicaciones. La aversi\u00f3n condicionada al sabor tiene la particularidad de ser una forma de aprendizaje r\u00e1pida siendo a veces suficiente un solo evento de asociaci\u00f3n para generar la aversi\u00f3n si los est\u00edmulos son novedosos. Como procedimiento, la aversi\u00f3n condicionada al sabor es utilizada muy extensamente en investigaci\u00f3n b\u00e1sica en psicolog\u00eda experimental y comparada, y de forma aplicada en esta y otras disciplinas. Experiencias de aversi\u00f3n condicionada en ovinos y caprinos han permitido generar sistemas de pastoreo en explotaciones de frutales con el fin de desmalezar el terreno sin consumir la hoja o brotes de los arboles productivos, evitando con ello el uso de pesticidas. En estos estudios se presenta la hoja que se busca proteger para que el animal la consuma, seguida de la administraci\u00f3n de LiCl, lo cual genera malestar gastrointestinal y como resultado, el rechazo selectivo de este alimento por parte de los animales prefiriendo el consumo de la maleza que se encuentra alrededor de los cultivos. El cultivo de frutales supone una de las actividades econ\u00f3micas m\u00e1s importantes de la Regi\u00f3n de O'Higgins, por lo que el uso de estrategias agropecuarias sostenibles mediante el establecimiento de aversi\u00f3n condicionada podr\u00eda ser de gran inter\u00e9s para la regi\u00f3n. Resultados no publicados de aversiones condicionadas para el control de malezas en vi\u00f1as y otras producciones agr\u00edcolas en Chile han sido auspiciosos. Sin embargo, la aversi\u00f3n condicionada a las hojas de los frutales no ha resultado ser persistente en el tiempo. Una aversi\u00f3n inestable y poco duradera supondr\u00eda un riesgo para los agricultores, que podr\u00edan ver malogrados sus cultivos si los animales comenzaran a elegirlos como alimento. La investigaci\u00f3n b\u00e1sica en psicolog\u00eda del aprendizaje ha aportado conocimiento \u00fatil para dise\u00f1ar estrategias dirigidas a fortalecer aversiones condicionadas. Por ejemplo, aunque existe poca informaci\u00f3n al respecto, el aprendizaje o condicionamiento prenatal y el aprendizaje observacional podr\u00edan jugar un papel importante a la hora fortalecer aprendizajes por condicionamiento cl\u00e1sico. El objetivo del presente proyecto es estudiar el efecto del aprendizaje prenatal y del aprendizaje social-observacional en la adquisici\u00f3n y la extinci\u00f3n de aversi\u00f3n condicionada a hojas de frutales en ovinos, a fin de implementar un sistema eficaz, sostenible y org\u00e1nico de explotaci\u00f3n agropecuaria en la Regi\u00f3n de O'Higgins. Un total de 48 ovejas adultas en gestaci\u00f3n temprana y sus cr\u00edas ser\u00e1n utilizados con el fin de estudiar el efecto del aprendizaje prenatal y social sobre la adquisici\u00f3n y resistencia a la extinci\u00f3n de aversiones condicionadas. Para esto se realizar\u00e1 un dise\u00f1o factorial de 2x2 en donde ovejas en gestaci\u00f3n tard\u00eda se someter\u00e1n (n24) o no (n24) a aversi\u00f3n condicionada asociando hojas de frutales con LiCL. La mitad de los corderos de cada grupo observaran a sus madres durante la conducta de consumo. Posteriormente los corderos de cada grupo se someter\u00e1n tras el destete a aversi\u00f3n condicionada de manera directa asociando las mismas hojas de frutales con LiCl. Se cuantificar\u00e1 el periodo de extinci\u00f3n de la aversi\u00f3n condicionada en cada cordero, analizando el consumo y palatabilidad percibida por las hojas. En tanto que el cultivo de frutales, as\u00ed como la explotaci\u00f3n ganadera son actividades econ\u00f3micas muy relevantes en la regi\u00f3n de O\u0092Higgins el \u00e9xito del proyecto podr\u00eda ser relevante para su desarrollo sostenible; 1) posibilitando la comercializaci\u00f3n de productos agr\u00edcolas org\u00e1nicos, libres de pesticidas y 2) permitiendo la nutrici\u00f3n de ganado ovino frente a una crisis h\u00eddrica que cada vez hace m\u00e1s escaso el acceso a forraje fresco. El conocimiento generado a partir de la colaboraci\u00f3n del \u00e1rea de ciencia animal y de psicolog\u00eda comparada abre una gran oportunidad para el desarrollo de ciencia b\u00e1sica y aplicada en nuestra regi\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2022 - Octubre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26630\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desarrollo de familias de medios-hermanos de Lagenaria siceraria para evaluaci\u00f3n de las tasas de injertaci\u00f3n-compatibilidad con sand\u00eda y del sistema de arquitectura radical en condiciones de riego deficitario\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26630\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26630\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Chile es uno de los principales pa\u00edses donde se llevan a cabo diversos programas de mejoramiento gen\u00e9tico de plantas. En estos, se eval\u00faa, selecciona y multiplica el germoplasma de diversos cultivos para desarrollar nuevos cultivares y\/o variedades vegetales. En ese contexto, durante d\u00e9cadas los fitomejoradores se han centrado tradicionalmente en la selecci\u00f3n direccional o artificial de las caracter\u00edsticas de las plantas para obtener mayores rendimientos en ambientes o condiciones particulares. De hecho, la selecci\u00f3n artificial ha producido cultivares notablemente productivos que son estables en diversos ambientes y\/o localidades. Por otro lado, la capacidad de una planta para modificar su fenotipo en respuesta al medio ambiente (es decir, la plasticidad) se ha propuesto como objetivo de mejoramiento para aumentar la productividad agr\u00edcola.\r\n\r\nSe sabe que la plasticidad del fenotipo corresponde a un rasgo complejo con base hereditaria, y durante la \u00faltima d\u00e9cada varios especialistas han comenzado a estudiarla en diversos cultivos y rasgos. La mayor\u00eda de los rasgos incluyen morfolog\u00eda, rendimiento de grano y resistencia a diferentes estreses de tipo abi\u00f3tico, que son deseables para fines de fitomejoramiento. Espec\u00edficamente, la plasticidad de los rasgos de la ra\u00edz se ha propuesto como un objetivo clave para el desarrollo de cultivos m\u00e1s productivos en ambientes variables, especialmente en condiciones de d\u00e9ficit h\u00eddrico. \r\n\r\nPara dar continuidad al proyecto Fondecyt iniciaci\u00f3n 2018-2022, en la propuesta del fondo puente se plantea generar una poblaci\u00f3n de familias de medios-hermanos de Lagenaria siceraria para su evaluaci\u00f3n en experimentos de campo en condiciones de d\u00e9ficit h\u00eddrico. En este contexto, los objetivos espec\u00edficos planteados son:\r\n\r\nEvaluar el porcentaje de injertaci\u00f3n en una poblaci\u00f3n de familia de medios hermanos de L. siceraria con variedades de sand\u00eda mediante tasas de prendimiento-compatibilidad \r\nCaracterizar el sistema de arquitectura de ra\u00edces en una poblaci\u00f3n de familia de medios-hermanos de Lagenaria siceraria\r\n \r\nPara lograr lo anterior, se plantean las siguientes actividades: 1) ingresar material gen\u00e9tico de L. siceraria (en forma de semillas) desde Banco de Germoplasma de Jap\u00f3n, 2) multiplicar semillas y generar una progenie de familias de medios-hermanos, 3) injertar estos portainjertos con variedad(es) comercial(es) de sand\u00eda y evaluar las tasas de prendimiento-compatibilidad de la injertaci\u00f3n y 4) caracterizar los rasgos de la arquitectura del sistema radical en condiciones de riego deficitario. \r\n\r\nEn detalle, los aspectos que pretende abordar el proyecto puente se plantean con el prop\u00f3sito de fortalecer y mejorar la competitividad del PI en t\u00e9rmino de publicaciones. El desarrollo de estas actividades dar\u00e1 continuidad a la investigaci\u00f3n del PI y permitir\u00eda aumentar el n\u00famero e impacto de las publicaciones para una pr\u00f3xima postulaci\u00f3n a fondos externos, o en su defecto avanzar con la investigaci\u00f3n para no afectar los tiempos de desarrollo de la investigaci\u00f3n del PI. Por otra parte, este fondo apoyar\u00e1 la investigaci\u00f3n del PI, considerando su reciente postulaci\u00f3n al concurso Fondecyt Regular.\r\n\r\nFinalmente, esta investigaci\u00f3n representa una propuesta novedosa que contribuye al estudio de la plasticidad de los rasgos de la ra\u00edz y la variaci\u00f3n de la arquitectura del sistema radical en una poblaci\u00f3n de familias de medios hermanos de L. siceraria en el contexto de un programa de mejoramiento gen\u00e9tico. Adem\u00e1s, este trabajo tambi\u00e9n podr\u00e1 contribuir con la identificaci\u00f3n de genes y alelos que ser\u00edan relevantes para establecer las diferencias moleculares en las respuestas pl\u00e1sticas de L. siceraria tanto en condiciones de d\u00e9ficit h\u00eddrico y normales de riego. De hecho, tambi\u00e9n se espera que algunas de estas accesiones sean consideradas en futuras investigaciones como portainjertos potenciales para cucurbit\u00e1ceas en ambientes espec\u00edficos.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2022 - Agosto 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Codelco<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26288\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            CONVENIO DE COOPERACI\u00d3N TECNOL\u00d3GICA PARA INVESTIGACION Y DESARROLLO &#8211; ESTUDIO DE EVALUACION DEL USO DE AGUAS CLARAS DEL EMBALSE CAR\u00c9N CON FINES AGRICOLAS\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26288\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26288\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]OBJETIVOS:\r\n\u0095\tEvaluar efecto de aguas claras del Embalse Car\u00e9n, mediante ensayos de toxicidad aguda con semillas de lechuga (lactuca sativa). \r\n\u0095\tDeterminar la producci\u00f3n de biomasa de los cultivos en estudio, para ensayos llevados a cabo en macetas. \r\n\u0095\tCaracterizar qu\u00edmicamente los lixiviados de suelo agr\u00edcola para los ensayos de macetas.\r\n\u0095\tEvaluar efecto del riego sobre las propiedades qu\u00edmicas, f\u00edsicas y biol\u00f3gicas del suelo en parcelas experimentales de 50 m2. \r\n\u0095\tEvaluar la acumulaci\u00f3n de compuestos inorg\u00e1nicos, tales como metales pesados en el suelo agr\u00edcola de las parcelas experimentales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> PID2022-141517NB-I00<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2022 - Agosto 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Ciencia e Innovaci\u00f3n, Gobierno de Espa\u00f1a.<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26443\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Proyecto Body Care: Trabajando hacia la satisfacci\u00f3n corporal en adolescentes y j\u00f3venes\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26443\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26443\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Participo como parte del equipo de trabajo del proyecto mencionado, el cual est\u00e1 dirigido por la Dra. Ana Andr\u00e9s Valle, qui\u00e9n es acad\u00e9mica de la Universidad Ramon Llull de Espa\u00f1a. El proyecto cuenta con un financiamiento para 4 a\u00f1os, consistente en 61.500 euros otorgados por el Ministerio de Ciencia e Innovaci\u00f3n del Gobierno de Espa\u00f1a. Se busca, mediante esta investigaci\u00f3n, evaluar la efectividad de una intervenci\u00f3n centrada en mejorar la satisfacci\u00f3n corporal de adolescentes y J\u00f3venes[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2022 - Junio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26530\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26530\" aria-expanded=\"false\" aria-controls=\"collapse-26530\">\n                                            Moral Balancing Project\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26530\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26530\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The phenomenon of moral balancing posits that upon taking ethical actions, people feel licensed to take unethical ones while maintaining a relatively stable moral self-image. Contrastingly, some empirical evidence points to consistency \u0096 people\u0092s ethical actions spill over to their subsequent behaviours and intentions. \r\nSo which one is it \u0096 when do people engage in licensing and when do they tend to be consistent? This question has implications for the complex global challenge of climate change, an issue that requires sustained pro-environmental actions. Therefore, we are conducting a Manylabs project to test moral balancing of pro-environmental behavior. To address existing gaps in literature, we are conducting a culturally diverse, behaviourally robust and high-powered test of moral balancing.\r\n\r\nConceived at the Moral Judgement and Behaviour workshop of the EASP 2022 Summer School in Wroc&#322;aw, Poland, this international collaboration is now joined by 150+ collaborators from over 40 countries.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2022 - Diciembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Fundaci\u00f3n para la Innovaci\u00f3n Agraria - FIA<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26531\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Salud mental, g\u00e9nero y cuidados, en las personas trabajadoras de salud durante la pandemia COVID-19\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26531\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26531\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto financiaci\u00f3n PICTO-2022- GENERO00045. \r\nEl equipo de investigaci\u00f3n integra las disciplinas en aspectos jur\u00eddicos y de derechos humanos, salud mental, medicina,\r\nsociolog\u00eda, estad\u00edsticas y especialistas en desarrollo local; ciencias pol\u00edticas, justicia de g\u00e9nero y planificaci\u00f3n estrat\u00e9gica con enfoque de g\u00e9nero. Es un equipo interdisciplinar y contribuye al campo de los cuidados, en la incorporaci\u00f3n del enfoque de g\u00e9nero; desarrollo territorial y derechos.\r\nhttps:\/\/www.argentina.gob.ar\/noticias\/se-presentaron-los-proyectos-seleccionados-de-la-convocatoria-picto-genero[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2022 - Septiembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26657\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Dise\u00f1o \u00f3ptimo de red de monitoreo de calidad de aire para medici\u00f3n de impacto en salud respiratoria\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26657\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26657\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La contaminaci\u00f3n ambiental extradomiciliaria es un importante problema de salud ambiental ya que es responsable del 7,6% de la mortalidad anual total y de la p\u00e9rdida de 103,1 millones de a\u00f1os de vida saludable. Entre algunos de los efectos adversos que se han reportado para el Material Particulado, uno de los principales contaminantes, se encuentran aumento en la mortalidad, morbilidad, muerte prematura, enfermedades cardiovasculares y respiratorias, c\u00e1ncer de pulm\u00f3n, impacto adverso en la actividad del sistema nervioso central que resulta en deterioro cognitivo, y efectos nocivos sobre el desarrollo fetal y el embarazo, afectando mayormente a grupos m\u00e1s vulnerables. Si bien, a nivel global, se cuentan con estrategias y criterios de monitoreo de calidad del aire para identificar la concentraci\u00f3n de los contaminantes relacionados con la salud, es posible que estos no permitan analizar con mayor profundidad las diferencias en la distribuci\u00f3n geogr\u00e1fica de los contaminantes y su impacto en poblaciones espec\u00edficas. \r\nEn ese sentido, el presente proyecto tiene el objetivo de establecer una metodolog\u00eda para la generaci\u00f3n de un mapa confiable de la contaminaci\u00f3n del aire a partir de una red de monitoreo, el cual permita correlacionar de manera m\u00e1s precisa a trav\u00e9s de modelos de interpolaci\u00f3n, la contaminaci\u00f3n del aire con los problemas de salud respiratorio de las personas del sector considerado, hacer una validaci\u00f3n de la metodolog\u00eda propuesta con un programa piloto en un \u00e1rea a determinar de la comuna de Rancagua y realizar divulgaci\u00f3n de resultados en colegios y jardines de la regi\u00f3n con la finalidad de generar un debate m\u00e1s amplio y democr\u00e1tico sobre tanto de pr\u00e1cticas personales as\u00ed como de las nuevas pol\u00edticas relacionadas con la contaminaci\u00f3n del aire.\r\nPara esto se propone emplear diversos m\u00e9todos propios de cada disciplina. Primeramente, se estimar\u00e1 un radio m\u00e1ximo de cobertura de un sensor dentro del cual se garantice cierto grado de confianza (Variograma emp\u00edrico) respecto de los valores entregados por el sensor como promedios representativos, para as\u00ed determinar el tama\u00f1o\/forma del \u00e1rea geogr\u00e1fica total donde instalar la red de sensores (Obj 1). Con esta informaci\u00f3n se determinar\u00e1 una configuraci\u00f3n inicial de los sensores en un \u00e1rea geogr\u00e1fica determinada considerando la capacidad de la red, usando como ubicaci\u00f3n potencial establecimientos educativos. Luego se har\u00e1 un an\u00e1lisis estad\u00edstico con los datos proporcionados por la red y por sensores m\u00f3viles para determinar una nueva configuraci\u00f3n que maximice la confianza de la nueva interpolaci\u00f3n. Una vez instalados los sensores y a partir de los datos entregados por ellos se escoger\u00e1 una nueva configuraci\u00f3n a trav\u00e9s de un an\u00e1lisis estad\u00edstico de covarianzas (Obj 2). Adem\u00e1s, se realizar\u00e1 un estudio ecol\u00f3gico para correlacionar las mediciones de contaminaci\u00f3n de aire y algunos indicadores de salud respiratoria y atenci\u00f3n de salud considerando distintos puntos geogr\u00e1ficos de la sexta regi\u00f3n (Obj 3). Finalmente, el proyecto desarrollar\u00e1 un plan de educaci\u00f3n ambiental para concientizar sobre el tema y favorecer el cambio de comportamientos a nivel individual y comunitario (Obj 4).\r\nCon este proyecto se espera abordar con una visi\u00f3n interdisciplinaria un tema que es de especial preocupaci\u00f3n en la regi\u00f3n, como es la contaminaci\u00f3n ambiental, fortaleciendo esta l\u00ednea de investigaci\u00f3n tanto en el instituto de ingenier\u00eda como en el de Salud, involucrando de forma activa tambi\u00e9n a estudiantes de pregrado.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2022 - Septiembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26679\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Dise\u00f1o \u00f3ptimo de red de monitoreo de calidad de aire para medici\u00f3n de impacto en salud respiratoria\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26679\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26679\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La contaminaci\u00f3n ambiental extradomiciliaria es un importante problema de salud ambiental ya que es responsable del 7,6% de la mortalidad anual total y de la p\u00e9rdida de 103,1 millones de a\u00f1os de vida saludable. Entre algunos de los efectos adversos que se han reportado para el Material Particulado, uno de los principales contaminantes, se encuentran aumento en la mortalidad, morbilidad, muerte prematura, enfermedades cardiovasculares y respiratorias, c\u00e1ncer de pulm\u00f3n, impacto adverso en la actividad del sistema nervioso central que resulta en deterioro cognitivo, y efectos nocivos sobre el desarrollo fetal y el embarazo, afectando mayormente a grupos m\u00e1s vulnerables. Si bien, a nivel global, se cuentan con estrategias y criterios de monitoreo de calidad del aire para identificar la concentraci\u00f3n de los contaminantes relacionados con la salud, es posible que estos no permitan analizar con mayor profundidad las diferencias en la distribuci\u00f3n geogr\u00e1fica de los contaminantes y su impacto en poblaciones espec\u00edficas. \r\nEn ese sentido, el presente proyecto tiene el objetivo de establecer una metodolog\u00eda para la generaci\u00f3n de un mapa confiable de la contaminaci\u00f3n del aire a partir de una red de monitoreo, el cual permita correlacionar de manera m\u00e1s precisa a trav\u00e9s de modelos de interpolaci\u00f3n, la contaminaci\u00f3n del aire con los problemas de salud respiratorio de las personas del sector considerado, hacer una validaci\u00f3n de la metodolog\u00eda propuesta con un programa piloto en un \u00e1rea a determinar de la comuna de Rancagua y realizar divulgaci\u00f3n de resultados en colegios y jardines de la regi\u00f3n con la finalidad de generar un debate m\u00e1s amplio y democr\u00e1tico sobre tanto de pr\u00e1cticas personales as\u00ed como de las nuevas pol\u00edticas relacionadas con la contaminaci\u00f3n del aire.\r\nPara esto se propone emplear diversos m\u00e9todos propios de cada disciplina. Primeramente, se estimar\u00e1 un radio m\u00e1ximo de cobertura de un sensor dentro del cual se garantice cierto grado de confianza (Variograma emp\u00edrico) respecto de los valores entregados por el sensor como promedios representativos, para as\u00ed determinar el tama\u00f1o\/forma del \u00e1rea geogr\u00e1fica total donde instalar la red de sensores (Obj 1). Con esta informaci\u00f3n se determinar\u00e1 una configuraci\u00f3n inicial de los sensores en un \u00e1rea geogr\u00e1fica determinada considerando la capacidad de la red, usando como ubicaci\u00f3n potencial establecimientos educativos. Luego se har\u00e1 un an\u00e1lisis estad\u00edstico con los datos proporcionados por la red y por sensores m\u00f3viles para determinar una nueva configuraci\u00f3n que maximice la confianza de la nueva interpolaci\u00f3n. Una vez instalados los sensores y a partir de los datos entregados por ellos se escoger\u00e1 una nueva configuraci\u00f3n a trav\u00e9s de un an\u00e1lisis estad\u00edstico de covarianzas (Obj 2). Adem\u00e1s, se realizar\u00e1 un estudio ecol\u00f3gico para correlacionar las mediciones de contaminaci\u00f3n de aire y algunos indicadores de salud respiratoria y atenci\u00f3n de salud considerando distintos puntos geogr\u00e1ficos de la sexta regi\u00f3n (Obj 3). Finalmente, el proyecto desarrollar\u00e1 un plan de educaci\u00f3n ambiental para concientizar sobre el tema y favorecer el cambio de comportamientos a nivel individual y comunitario (Obj 4).\r\nCon este proyecto se espera abordar con una visi\u00f3n interdisciplinaria un tema que es de especial preocupaci\u00f3n en la regi\u00f3n, como es la contaminaci\u00f3n ambiental, fortaleciendo esta l\u00ednea de investigaci\u00f3n tanto en el instituto de ingenier\u00eda como en el de Salud, involucrando de forma activa tambi\u00e9n a estudiantes de pregrado.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2022 - Diciembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Fundaci\u00f3n para la Innovaci\u00f3n Agraria - FIA<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26809\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Salud mental, g\u00e9nero y cuidados, en las personas trabajadoras de salud durante la pandemia COVID-19\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26809\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26809\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto financiaci\u00f3n PICTO-2022- GENERO00045. \r\nEl equipo de investigaci\u00f3n integra las disciplinas en aspectos jur\u00eddicos y de derechos humanos, salud mental, medicina,\r\nsociolog\u00eda, estad\u00edsticas y especialistas en desarrollo local; ciencias pol\u00edticas, justicia de g\u00e9nero y planificaci\u00f3n estrat\u00e9gica con enfoque de g\u00e9nero. Es un equipo interdisciplinar y contribuye al campo de los cuidados, en la incorporaci\u00f3n del enfoque de g\u00e9nero; desarrollo territorial y derechos.\r\nhttps:\/\/www.argentina.gob.ar\/noticias\/se-presentaron-los-proyectos-seleccionados-de-la-convocatoria-picto-genero[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2022 - Agosto 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>SPSSI Spring 2022 Researchers in the Global South Grants Program - The Society for the Psychological Study of Social Issues (USA)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26756\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26756\" aria-expanded=\"false\" aria-controls=\"collapse-26756\">\n                                            Postcolonial ideologies, recognition and reparation policies, and current intergroup relations: The Mapuche in Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26756\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26756\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The Mapuche are an indigenous group that has been involved in a conflict with the Chilean State for many years and we propose that studying postcolonial ideologies (Sibley, 2010), namely historical negation, symbolic exclusion and mestizaje, and their connections with current intergroup relations and demands for recognition and reparation on behalf of the Mapuche, deserves attention from social and political psychologists. Thus, through three interconnected studies, this project aims to analyze these postcolonial ideologies, their antecedents, and their association with intergroup attitudes and adherence to policies and demands for reparation and recognition on behalf of Mapuche people.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> URO2295<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2022 - Enero 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25988\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortalecimiento de estrategias comunitarias de promoci\u00f3n de la salud, prevenci\u00f3n y tratamiento temprano y oportuno de enfermedades cr\u00f3nicas no transmisibles con foco en actividad f\u00edsica y nutrici\u00f3n saludable\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25988\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25988\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]URO 2295. El Ministerio de Educaci\u00f3n a trav\u00e9s del Departamento de Fortalecimiento Institucional de la Subsecretaria de Educaci\u00f3n Superior financia proyectos que permitan contribuir al desarrollo social y territorial, a nivel local y\/o regional, a trav\u00e9s de la generaci\u00f3n compartida de conocimientos, oportunidades de desarrollo y\/o beneficios entre las instituciones de educaci\u00f3n superior y los actores sociales, tanto p\u00fablicos como privados. En este contexto, este proyecto busca generar estrategias eficaces \u0096 con la comunidad y distintos actores sociales de la regi\u00f3n \u0096 y basadas en la evidencia que aborden el aumento de la prevalencia de enfermedades cr\u00f3nicas no transmisibles a trav\u00e9s de la mejora de los patrones de actividad f\u00edsica y alimentarios de la poblaci\u00f3n regional. \r\nObjetivo general: Fortalecer las estrategias comunitarias de promoci\u00f3n de la salud, prevenci\u00f3n y tratamiento temprano y oportuno de enfermedades cr\u00f3nicas no transmisibles en la Regi\u00f3n de O\u0092Higgins con foco en actividad f\u00edsica y nutrici\u00f3n saludable[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> URO2295<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2022 - Enero 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26015\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortalecimiento de estrategias comunitarias de promoci\u00f3n de la salud, prevenci\u00f3n y tratamiento temprano y oportuno de enfermedades cr\u00f3nicas no transmisibles con foco en actividad f\u00edsica y nutrici\u00f3n saludable\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26015\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26015\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]URO 2295. El Ministerio de Educaci\u00f3n a trav\u00e9s del Departamento de Fortalecimiento Institucional de la Subsecretaria de Educaci\u00f3n Superior financia proyectos que permitan contribuir al desarrollo social y territorial, a nivel local y\/o regional, a trav\u00e9s de la generaci\u00f3n compartida de conocimientos, oportunidades de desarrollo y\/o beneficios entre las instituciones de educaci\u00f3n superior y los actores sociales, tanto p\u00fablicos como privados. En este contexto, este proyecto busca generar estrategias eficaces \u0096 con la comunidad y distintos actores sociales de la regi\u00f3n \u0096 y basadas en la evidencia que aborden el aumento de la prevalencia de enfermedades cr\u00f3nicas no transmisibles a trav\u00e9s de la mejora de los patrones de actividad f\u00edsica y alimentarios de la poblaci\u00f3n regional. \r\nObjetivo general: Fortalecer las estrategias comunitarias de promoci\u00f3n de la salud, prevenci\u00f3n y tratamiento temprano y oportuno de enfermedades cr\u00f3nicas no transmisibles en la Regi\u00f3n de O\u0092Higgins con foco en actividad f\u00edsica y nutrici\u00f3n saludable[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> URO2295<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2022 - Enero 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26134\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortalecimiento de estrategias comunitarias de promoci\u00f3n de la salud, prevenci\u00f3n y tratamiento temprano y oportuno de enfermedades cr\u00f3nicas no transmisibles con foco en actividad f\u00edsica y nutrici\u00f3n saludable\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26134\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26134\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]URO 2295. El Ministerio de Educaci\u00f3n a trav\u00e9s del Departamento de Fortalecimiento Institucional de la Subsecretaria de Educaci\u00f3n Superior financia proyectos que permitan contribuir al desarrollo social y territorial, a nivel local y\/o regional, a trav\u00e9s de la generaci\u00f3n compartida de conocimientos, oportunidades de desarrollo y\/o beneficios entre las instituciones de educaci\u00f3n superior y los actores sociales, tanto p\u00fablicos como privados. En este contexto, este proyecto busca generar estrategias eficaces \u0096 con la comunidad y distintos actores sociales de la regi\u00f3n \u0096 y basadas en la evidencia que aborden el aumento de la prevalencia de enfermedades cr\u00f3nicas no transmisibles a trav\u00e9s de la mejora de los patrones de actividad f\u00edsica y alimentarios de la poblaci\u00f3n regional. \r\nObjetivo general: Fortalecer las estrategias comunitarias de promoci\u00f3n de la salud, prevenci\u00f3n y tratamiento temprano y oportuno de enfermedades cr\u00f3nicas no transmisibles en la Regi\u00f3n de O\u0092Higgins con foco en actividad f\u00edsica y nutrici\u00f3n saludable[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> URO2295<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2022 - Enero 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26156\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortalecimiento de estrategias comunitarias de promoci\u00f3n de la salud, prevenci\u00f3n y tratamiento temprano y oportuno de enfermedades cr\u00f3nicas no transmisibles con foco en actividad f\u00edsica y nutrici\u00f3n saludable\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26156\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26156\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]URO 2295. El Ministerio de Educaci\u00f3n a trav\u00e9s del Departamento de Fortalecimiento Institucional de la Subsecretaria de Educaci\u00f3n Superior financia proyectos que permitan contribuir al desarrollo social y territorial, a nivel local y\/o regional, a trav\u00e9s de la generaci\u00f3n compartida de conocimientos, oportunidades de desarrollo y\/o beneficios entre las instituciones de educaci\u00f3n superior y los actores sociales, tanto p\u00fablicos como privados. En este contexto, este proyecto busca generar estrategias eficaces \u0096 con la comunidad y distintos actores sociales de la regi\u00f3n \u0096 y basadas en la evidencia que aborden el aumento de la prevalencia de enfermedades cr\u00f3nicas no transmisibles a trav\u00e9s de la mejora de los patrones de actividad f\u00edsica y alimentarios de la poblaci\u00f3n regional. \r\nObjetivo general: Fortalecer las estrategias comunitarias de promoci\u00f3n de la salud, prevenci\u00f3n y tratamiento temprano y oportuno de enfermedades cr\u00f3nicas no transmisibles en la Regi\u00f3n de O\u0092Higgins con foco en actividad f\u00edsica y nutrici\u00f3n saludable[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> URO2295<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2022 - Enero 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26193\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortalecimiento de estrategias comunitarias de promoci\u00f3n de la salud, prevenci\u00f3n y tratamiento temprano y oportuno de enfermedades cr\u00f3nicas no transmisibles con foco en actividad f\u00edsica y nutrici\u00f3n saludable\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26193\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26193\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]URO 2295. El Ministerio de Educaci\u00f3n a trav\u00e9s del Departamento de Fortalecimiento Institucional de la Subsecretaria de Educaci\u00f3n Superior financia proyectos que permitan contribuir al desarrollo social y territorial, a nivel local y\/o regional, a trav\u00e9s de la generaci\u00f3n compartida de conocimientos, oportunidades de desarrollo y\/o beneficios entre las instituciones de educaci\u00f3n superior y los actores sociales, tanto p\u00fablicos como privados. En este contexto, este proyecto busca generar estrategias eficaces \u0096 con la comunidad y distintos actores sociales de la regi\u00f3n \u0096 y basadas en la evidencia que aborden el aumento de la prevalencia de enfermedades cr\u00f3nicas no transmisibles a trav\u00e9s de la mejora de los patrones de actividad f\u00edsica y alimentarios de la poblaci\u00f3n regional. \r\nObjetivo general: Fortalecer las estrategias comunitarias de promoci\u00f3n de la salud, prevenci\u00f3n y tratamiento temprano y oportuno de enfermedades cr\u00f3nicas no transmisibles en la Regi\u00f3n de O\u0092Higgins con foco en actividad f\u00edsica y nutrici\u00f3n saludable[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> URO2295<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2022 - Enero 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26432\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortalecimiento de estrategias comunitarias de promoci\u00f3n de la salud, prevenci\u00f3n y tratamiento temprano y oportuno de enfermedades cr\u00f3nicas no transmisibles con foco en actividad f\u00edsica y nutrici\u00f3n saludable\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26432\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26432\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]URO 2295. El Ministerio de Educaci\u00f3n a trav\u00e9s del Departamento de Fortalecimiento Institucional de la Subsecretaria de Educaci\u00f3n Superior financia proyectos que permitan contribuir al desarrollo social y territorial, a nivel local y\/o regional, a trav\u00e9s de la generaci\u00f3n compartida de conocimientos, oportunidades de desarrollo y\/o beneficios entre las instituciones de educaci\u00f3n superior y los actores sociales, tanto p\u00fablicos como privados. En este contexto, este proyecto busca generar estrategias eficaces \u0096 con la comunidad y distintos actores sociales de la regi\u00f3n \u0096 y basadas en la evidencia que aborden el aumento de la prevalencia de enfermedades cr\u00f3nicas no transmisibles a trav\u00e9s de la mejora de los patrones de actividad f\u00edsica y alimentarios de la poblaci\u00f3n regional. \r\nObjetivo general: Fortalecer las estrategias comunitarias de promoci\u00f3n de la salud, prevenci\u00f3n y tratamiento temprano y oportuno de enfermedades cr\u00f3nicas no transmisibles en la Regi\u00f3n de O\u0092Higgins con foco en actividad f\u00edsica y nutrici\u00f3n saludable[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2022 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Centro Interuniversitario de Envejecimiento Saludable-Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26439\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Caracterizaci\u00f3n del patr\u00f3n alimentario y perfil socio-sanitario de personas mayores chilenas: Macrozonas Norte, Centro-Sur y Sur-Austral\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26439\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26439\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proceso de envejecimiento en pa\u00edses como Chile ha sido m\u00e1s r\u00e1pido y m\u00e1s reciente que en los\r\npa\u00edses desarrollados, con un crecimiento estimado casi exponencial. Como resultado, no ha habido suficiente\r\npreparaci\u00f3n de pol\u00edticas p\u00fablicas y sociales para permitir este proceso. La alta vulnerabilidad\r\nsocioecon\u00f3mica de la mayor\u00eda de las personas mayores (PM) en Chile, asociada a la inequidad, constituye\r\nuna brecha dif\u00edcil de atravesar sin medidas estructurales.\r\nA nivel global se ha observado un cambio en los patrones alimentarios hacia el consumo de dietas con una\r\nalta densidad cal\u00f3rica, proveniente de az\u00facares y grasas, as\u00ed como el consumo de productos procesados altos\r\nen az\u00facar, sodio y un valor nutricional m\u00ednimo. En el patr\u00f3n alimentario de cada familia y de cada individuo\r\nen particular influyen factores socioculturales, emocionales, econ\u00f3micos (el costo y la asequibilidad de los\r\nalimentos), as\u00ed como el entorno alimentario. Hoy en d\u00eda, sin embargo, se reconoce la importancia de un\r\npatr\u00f3n alimentario saludable y sostenible en todas las etapas de la vida, y su influencia en el envejecimiento\r\nsaludable.\r\nCon frecuencia, las PM se muestran m\u00e1s vulnerables a las deficiencias nutricionales, por los cambios\r\nfisiol\u00f3gicos, f\u00edsicos, ps\u00edquicos y sociales, debido en gran parte a la disminuci\u00f3n del apetito, as\u00ed como la\r\ncantidad de alimentos ingeridos. Se ha demostrado que la deficiencia de vitamina D est\u00e1 fuertemente\r\nasociada con un aumento de la mortalidad general, as\u00ed como con las muertes por enfermedades espec\u00edficas\r\nrelacionadas con el envejecimiento, como las enfermedades cardiovasculares y diferentes formas de c\u00e1ncer,\r\nadem\u00e1s de contribuir a la inmunosenescencia. De forma similar, la acumulaci\u00f3n de productos finales de\r\nglicaci\u00f3n avanzada (AGEs) ha sido asociada a la etiolog\u00eda de numerosas enfermedades cr\u00f3nicas no\r\ntransmisibles (ENT) y el proceso de envejecimiento. Nuestra propuesta tiene como objetivo, desarrollar un\r\nestudio piloto para determinar y caracterizar el perfil sociosanitario y el patr\u00f3n alimentario de PM chilenas\r\nen relaci\u00f3n a su origen territorial: macrozonas Norte, Centro-Sur y Sur-Austral. Para ello, se pretende\r\nconocer el patr\u00f3n alimentario de tres subgrupos de PM autovalentes que viven en las macrozonas se\u00f1aladas.\r\nDada la interdisciplinariedad del equipo de trabajo, la informaci\u00f3n a recabar incluye tipo y cantidad de\r\nalimentos, como tambi\u00e9n la detecci\u00f3n de aspectos sociosanitarios (estado nutricional, salud bucal,\r\ncomorbilidades, tratamientos farmacol\u00f3gicos, entre otros), incluyendo factores psicoemocionales\r\n(aislamiento geogr\u00e1fico, social, redes de apoyo) y de salud mental, que afectan el patr\u00f3n de ingesta\r\nalimentaria. La informaci\u00f3n a obtener a partir de datos disponibles (encuestas de salud, de consumo\r\nalimentario y otras de acceso p\u00fablico), se complementar\u00e1 con la medici\u00f3n de biomarcadores de\r\nfuncionalidad y alteraciones metab\u00f3licas (dinamometr\u00eda, AGEs en piel, niveles de vitamina D, glicemia y AGEs\r\nen sangre), sensaci\u00f3n de bienestar y calidad de vida, entre otros.\r\nLa informaci\u00f3n analizada ser\u00e1 relevante para responder la pregunta de investigaci\u00f3n y buscar asociaciones\r\nentre el patr\u00f3n alimentario territorial y la presencia de comorbilidades que condicionan el fenotipo del\r\nenvejecimiento. Esta informaci\u00f3n ser\u00e1 un insumo de alta calidad para el Observatorio del CIES, que podr\u00e1 ser\r\nentregada a los tomadores de decisiones sobre pol\u00edticas p\u00fablicas en materia de salud y bienestar de las PM,\r\nconsiderando la territorialidad del pa\u00eds.\r\nDadas las condiciones de esta convocatoria, el estudio tendr\u00e1 un car\u00e1cter piloto, con un n\u00famero de PM\r\nparticipantes estimado en 300, considerando subgrupos de 100 PM por macrozona estudiada. Este el primer proyecto interuniversitario y transdisciplinario que se plantea en este tema dentro del CIES, y permitir\u00e1 sentar las bases con antecedentes que permitan postular con posterioridad a fondos concursables externos al Centro y ampliar el alcance de los resultados.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2022 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Centro Interuniversitario de Envejecimiento Saludable-Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26440\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fragilidad, sexualidad y su impacto en la calidad de vida en personas mayores residentes en  las regiones de Antofagasta, Coquimbo, O&#8217;Higgins, Maule y Los Lagos, durante el periodo 2023-2024\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26440\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26440\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La sexualidad es uno de los aspectos cuya importancia es destacada en tem\u00e1ticas de asociaci\u00f3n o integraci\u00f3n de la calidad de vida en la vejez, y debiera ser considerada en la valorizaci\u00f3n en el campo asistencial en la prestaci\u00f3n de servicios de salud. De all\u00ed la importancia de una mejor comprensi\u00f3n de la sexualidad en las personas mayores que permitan avanzar en investigaci\u00f3n, educaci\u00f3n, pol\u00edticas y, especialmente en la atenci\u00f3n de salud a esta poblaci\u00f3n (MINSAL, 2010). Las investigaciones se\u00f1alan que el amor y la sexualidad contin\u00faan siendo aspectos de gran importancia en la vida del ser humano, a pesar de que cada grupo generacional tiene sus propias percepciones respecto a la misma, las cuales pueden limitar o favorecer su expresi\u00f3n y disfrute en la tercera edad (Torres, 2020). \r\nEl objetivo de este estudio es determinar la asociaci\u00f3n entre la sexualidad y la situaci\u00f3n de fragilidad y el impacto que tiene esta relaci\u00f3n en la calidad de vida de las personas mayores residentes en cuatro regiones de Chile. Lo que implica caracterizar las dimensiones de la sexualidad y describir la situaci\u00f3n de fragilidad en las personas mayores. \r\nPara los efectos, se propone realizar un estudio de tipo cuantitativo, transversal; con un tama\u00f1o muestral m\u00ednimo calculado de 500 personas mayores; considerando un margen de confianza del 95% y un margen de error de un 5% a nivel de las regiones seleccionadas; Antofagasta, Coquimbo, O\u0092Higgins y Los Lagos.\r\nLos resultados que se esperan obtener son contribuir al conocimiento de relaci\u00f3n entre la sexualidad, situaci\u00f3n fragilidad de las personas mayores, y su impacto en la calidad de vida. Adem\u00e1s, de identificar factores que representen riesgos para el desarrollo de una vida sexual saludable en personas mayores en situaci\u00f3n de fragilidad, como antecedentes para la generaci\u00f3n de Pol\u00edticas P\u00fablicas e intervenciones en los \u00e1mbitos en los diferentes niveles de salud.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> URO2295<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2022 - Enero 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26608\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortalecimiento de estrategias comunitarias de promoci\u00f3n de la salud, prevenci\u00f3n y tratamiento temprano y oportuno de enfermedades cr\u00f3nicas no transmisibles con foco en actividad f\u00edsica y nutrici\u00f3n saludable\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26608\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26608\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]URO 2295. El Ministerio de Educaci\u00f3n a trav\u00e9s del Departamento de Fortalecimiento Institucional de la Subsecretaria de Educaci\u00f3n Superior financia proyectos que permitan contribuir al desarrollo social y territorial, a nivel local y\/o regional, a trav\u00e9s de la generaci\u00f3n compartida de conocimientos, oportunidades de desarrollo y\/o beneficios entre las instituciones de educaci\u00f3n superior y los actores sociales, tanto p\u00fablicos como privados. En este contexto, este proyecto busca generar estrategias eficaces \u0096 con la comunidad y distintos actores sociales de la regi\u00f3n \u0096 y basadas en la evidencia que aborden el aumento de la prevalencia de enfermedades cr\u00f3nicas no transmisibles a trav\u00e9s de la mejora de los patrones de actividad f\u00edsica y alimentarios de la poblaci\u00f3n regional. \r\nObjetivo general: Fortalecer las estrategias comunitarias de promoci\u00f3n de la salud, prevenci\u00f3n y tratamiento temprano y oportuno de enfermedades cr\u00f3nicas no transmisibles en la Regi\u00f3n de O\u0092Higgins con foco en actividad f\u00edsica y nutrici\u00f3n saludable[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> URO2295<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2022 - Enero 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26659\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortalecimiento de estrategias comunitarias de promoci\u00f3n de la salud, prevenci\u00f3n y tratamiento temprano y oportuno de enfermedades cr\u00f3nicas no transmisibles con foco en actividad f\u00edsica y nutrici\u00f3n saludable\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26659\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26659\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]URO 2295. El Ministerio de Educaci\u00f3n a trav\u00e9s del Departamento de Fortalecimiento Institucional de la Subsecretaria de Educaci\u00f3n Superior financia proyectos que permitan contribuir al desarrollo social y territorial, a nivel local y\/o regional, a trav\u00e9s de la generaci\u00f3n compartida de conocimientos, oportunidades de desarrollo y\/o beneficios entre las instituciones de educaci\u00f3n superior y los actores sociales, tanto p\u00fablicos como privados. En este contexto, este proyecto busca generar estrategias eficaces \u0096 con la comunidad y distintos actores sociales de la regi\u00f3n \u0096 y basadas en la evidencia que aborden el aumento de la prevalencia de enfermedades cr\u00f3nicas no transmisibles a trav\u00e9s de la mejora de los patrones de actividad f\u00edsica y alimentarios de la poblaci\u00f3n regional. \r\nObjetivo general: Fortalecer las estrategias comunitarias de promoci\u00f3n de la salud, prevenci\u00f3n y tratamiento temprano y oportuno de enfermedades cr\u00f3nicas no transmisibles en la Regi\u00f3n de O\u0092Higgins con foco en actividad f\u00edsica y nutrici\u00f3n saludable[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> URO2295<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2022 - Enero 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26783\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortalecimiento de estrategias comunitarias de promoci\u00f3n de la salud, prevenci\u00f3n y tratamiento temprano y oportuno de enfermedades cr\u00f3nicas no transmisibles con foco en actividad f\u00edsica y nutrici\u00f3n saludable\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26783\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26783\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]URO 2295. El Ministerio de Educaci\u00f3n a trav\u00e9s del Departamento de Fortalecimiento Institucional de la Subsecretaria de Educaci\u00f3n Superior financia proyectos que permitan contribuir al desarrollo social y territorial, a nivel local y\/o regional, a trav\u00e9s de la generaci\u00f3n compartida de conocimientos, oportunidades de desarrollo y\/o beneficios entre las instituciones de educaci\u00f3n superior y los actores sociales, tanto p\u00fablicos como privados. En este contexto, este proyecto busca generar estrategias eficaces \u0096 con la comunidad y distintos actores sociales de la regi\u00f3n \u0096 y basadas en la evidencia que aborden el aumento de la prevalencia de enfermedades cr\u00f3nicas no transmisibles a trav\u00e9s de la mejora de los patrones de actividad f\u00edsica y alimentarios de la poblaci\u00f3n regional. \r\nObjetivo general: Fortalecer las estrategias comunitarias de promoci\u00f3n de la salud, prevenci\u00f3n y tratamiento temprano y oportuno de enfermedades cr\u00f3nicas no transmisibles en la Regi\u00f3n de O\u0092Higgins con foco en actividad f\u00edsica y nutrici\u00f3n saludable[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> URO2295<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2022 - Enero 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26808\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortalecimiento de estrategias comunitarias de promoci\u00f3n de la salud, prevenci\u00f3n y tratamiento temprano y oportuno de enfermedades cr\u00f3nicas no transmisibles con foco en actividad f\u00edsica y nutrici\u00f3n saludable\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26808\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26808\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]URO 2295. El Ministerio de Educaci\u00f3n a trav\u00e9s del Departamento de Fortalecimiento Institucional de la Subsecretaria de Educaci\u00f3n Superior financia proyectos que permitan contribuir al desarrollo social y territorial, a nivel local y\/o regional, a trav\u00e9s de la generaci\u00f3n compartida de conocimientos, oportunidades de desarrollo y\/o beneficios entre las instituciones de educaci\u00f3n superior y los actores sociales, tanto p\u00fablicos como privados. En este contexto, este proyecto busca generar estrategias eficaces \u0096 con la comunidad y distintos actores sociales de la regi\u00f3n \u0096 y basadas en la evidencia que aborden el aumento de la prevalencia de enfermedades cr\u00f3nicas no transmisibles a trav\u00e9s de la mejora de los patrones de actividad f\u00edsica y alimentarios de la poblaci\u00f3n regional. \r\nObjetivo general: Fortalecer las estrategias comunitarias de promoci\u00f3n de la salud, prevenci\u00f3n y tratamiento temprano y oportuno de enfermedades cr\u00f3nicas no transmisibles en la Regi\u00f3n de O\u0092Higgins con foco en actividad f\u00edsica y nutrici\u00f3n saludable[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> Fondap 15130009<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2022 - Diciembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26917\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Feminismo y ciencias sociales en Chile: Voces desde sus participantes\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26917\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26917\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetivo general de este proyecto es analizar las condiciones, pr\u00e1cticas y discursos feministas en el campo de las ciencias sociales en Chile, desde las experiencias de personas y comunidades que hist\u00f3ricamente han ocupado posiciones subordinadas en la producci\u00f3n de conocimiento, como mujeres, disidencias y personas ind\u00edgenas, desde una perspectiva feminista. El proyecto espera contribuir a sistematizar y difundir los avances y desaf\u00edos en t\u00e9rminos de equidad de g\u00e9nero en el campo de ciencias sociales en Chile.\r\n\r\nObjetivos espec\u00edficos:\r\n1. Caracterizar las condiciones de trabajo y criterios de productividad acad\u00e9mica en las ciencias sociales seg\u00fan grupos de posiciones subordinadas.\r\n2. Identificar discursos y pr\u00e1cticas feministas en el \u00e1rea de las ciencias sociales en Chile.\r\n3. Analizar el contexto territorial a partir del cual se desarrollan las condiciones, pr\u00e1cticas y discursos feministas en las ciencias sociales en Chile.\r\n4. Visibilizar la experiencia y las investigaciones de cientistas sociales, especialmente mujeres, disidencias y personas ind\u00edgenas, que analizan la producci\u00f3n de conocimiento y configuraci\u00f3n de la academia en Chile utilizando epistemolog\u00edas feministas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> EDITAL 02\/2022. APOIO \u00c0 PROJETO DE PESQUISA - UNIVERSAL\/FAPEMA - 06504\/22<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2022 - Agosto 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Funda\u00e7\u00e3o de Amparo \u00e0 Pesquisa e ao Desenvolvimento Cient\u00edfico   e   Tecnol\u00f3gico   do   Maranh\u00e3o   (FAPEMA)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27008\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27008\" aria-expanded=\"false\" aria-controls=\"collapse-27008\">\n                                            Manejos distintos com silicio e microrganismo do solo na produ\u00e7\u00e3o de gr\u00e3o e biomassa para alimenta\u00e7\u00e3o animal\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27008\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27008\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Nesta pesquisa se propoe a produ\u00e7\u00e3o de silagens de forrageiras anuais com uso de fertirriga\u00e7\u00e3o com Si e uso de microrganismos no solo, para aumenta a produ\u00e7\u00e3o de gr\u00e3os e silagens para ruminantes no per\u00edodo de estressafra (seca).[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> P\u00f3s-doutorado J\u00fanior 151642\/2022-2<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2022 - Julio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Consejo Nacional de Desarrollo Cient\u00edfico y Tecnol\u00f3gico-CNPq 25\/2021<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27013\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27013\" aria-expanded=\"false\" aria-controls=\"collapse-27013\">\n                                            Implica\u00e7\u00f5es das mudan\u00e7as no uso da terra e da cobertura vegetal sobre par\u00e2metros f\u00edsicos e qu\u00edmicos do solo e da vegeta\u00e7\u00e3o coexistente em uma ampla gama de escalas espaciais e temporais no Estado de Rio de Janeiro\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27013\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27013\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The state of Rio de Janeiro presents very varied relief forms, with marked topographic contrasts, with expressive spatial and temporal climatic variability. Besides these factors, the history of colonization and differentiated policies have contributed for the agricultural production in Rio de Janeiro to present distinct regional dynamics, with differentiation in land\r\noccupation and use and diversification of economic activities, which, as a function of the different levels of soil fragility, have generated different degrees of degradation. Carbon (C), nitrogen (N) and phosphorus (P) concentrations and stoichiometry play important roles in biogeochemical cycles of the ecosystems, yet it is still unclear how the allocations of C, N and P concentrations and stoichiometry of soils and its coexisting vegetation, including leaf litter, are related. Thus, the general objective of the project is to determine whether there are significant differences and influence of C:N:P stoichiometry ratios of the soil and coexisting vegetation including litter in each study area and examine how and to what extent soil and soil management conditions it influence the physical and soil chemistry in two contrasting physiographic regions of the State of Rio de Janeiro. Two regions of the State were selected to be studied, namely: Norte Fluminense and Costa Verde regions. These regions present different degrees of soil degradation due to different forms of use and occupation, soils and climate. The current scenario in some regions of the State of Rio de Janeiro shows that natural vulnerability and inadequate soil management can compromise the sustainability of the soil in the medium\r\nand long term. This proposal is associated with the thematic project entitled \u0093Soil quality indicators in areas with different histories of use and occupation in the State of Rio de Janeiro\u0094 funded by the Funda\u00e7\u00e3o de Amparo \u00e0 Pesquisa do Estado do Rio de Janeiro (FAPERJ) by through the Support Program for Thematic Projects in the State of Rio de Janeiro, FAPERJ\r\nNotice No. 28\/2021. In this context, it is essential to develop research that can serve as a guide for the adoption of conservationist soil management, essential for the sustainability of agricultural production. Furthermore, the results of studies developed with the collaboration of farmers in the field encourage them to adopt new habits in agricultural activities[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> N\u00b0CIES008<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26733\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estrategias de afrontamiento al estr\u00e9s durante el envejecimiento y su impacto en la memoria\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26733\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26733\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El estr\u00e9s es un factor de riesgo muy importante en el deterioro cognitivo, especialmente en medidas de\r\nmemoria y funciones ejecutivas, lo que es particularmente alarmante para la poblaci\u00f3n de personas mayores.\r\nEn este sentido, la manera de como afrontamos el estr\u00e9s determina sus efectos principalmente en la memoria.\r\nEste fen\u00f3meno no se ha estudiado durante el envejecimiento y en este proyecto abordaremos este desafio, desde estudios en humanos as\u00ed como en un modelo animal, explorando una hip\u00f3tesis en com\u00fan relacionada con las estrategias de afrontamiento al estr\u00e9s, cuando estas son activas reducen los efectos del estr\u00e9s sobre la memoria durante el envejecimiento. Esperamos entregar evidencias cient\u00edficas que mejorar\u00e1n la\r\nprevenci\u00f3n y el tratamiento de enfermedades relacionadas con el estr\u00e9s durante el envejecimiento, como la depresi\u00f3n y las demencias como el Alzheimer, que tienen un impacto social y econ\u00f3mico muy alto en la\r\npoblaci\u00f3n, lo cual se agudiza en un mundo que cada vez es mas estresante debido a la pandemia de COVID y el cambio clim\u00e1tico.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1221805<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26741\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            From compliance to resistance: How do citizens in Chile relate to and position themselves towards the police?\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26741\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26741\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto busca adoptar una perspectiva longitudinal para abordar las siguientes preguntas: \u00bfHasta qu\u00e9 punto la gente en Chile cree que la polic\u00eda es una instituci\u00f3n leg\u00edtima? \u00bfEst\u00e1n dispuestos a cumplir y colaborar con la polic\u00eda, por ejemplo, durante los controles de identidad, al denunciar un delito o durante las manifestaciones? \u00bfY bajo qu\u00e9 circunstancias est\u00e1n dispuestos a resistir las \u00f3rdenes de la polic\u00eda? \u00bfC\u00f3mo var\u00edan estas percepciones y disposiciones a lo largo del tiempo?[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2022 - Mayo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26884\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            A new biorationale framework for the management of insect targets through the use carbon quantum dots labeled-entomopathogenic nematodes in the soil\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26884\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26884\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Los nematodos entomopat\u00f3genos (NEP) son organismos que habitan en el suelo y que se han utilizado como agentes de control biol\u00f3gico de insectos en las \u00faltimas cuatro d\u00e9cadas . Estos organismos han ganado mucha atenci\u00f3n debido a su capacidad para buscar y matar a su hu\u00e9sped. El \u00fanico estadio capaz de matar insectos es el llamado juvenil infectivo (IJ). Una vez que los IJ han ingresado al hospedador, se libera un simbionte bacteriano y la muerte ocurre por septicemia entre las 48 a 96h. Los NEP son seguros para los organismos no-diana, amigables con el ambiente y pueden producirse en masa en grandes fermentadores. A pesar de todas las ventajas mencionadas, en ocasiones, el performance de estos nematodos no es tan bueno como se espera. Uno de los principales problemas relacionados con dichas fallas es la existencia de grandes vac\u00edos en su caracterizaci\u00f3n biol\u00f3gica y ecol\u00f3gica. Por ejemplo, la distribuci\u00f3n de NEP en el suelo (como una matriz tridimensional) despu\u00e9s de su aplicaci\u00f3n en el campo no se conoce totalmente porque la determinaci\u00f3n de su presencia depende de pruebas indirectas usando insectos trampas. Otra opci\u00f3n es el uso de RT-PCR para correlacionar la cantidad de ADN de una especie de NEP con una cantidad de individuos en una muestra de suelo, requiriendo mucho tiempo y esfuerzo. A\u00fan existen muchas preguntas que resolver, incluida la distribuci\u00f3n y persistencia en el suelo de los NEO, y la competencia entre las \"poblaciones naturales\" y las \"aplicadas comercialmente\", que siguen sin respuesta debido a la complejidad de la matriz del suelo.\r\nLa opci\u00f3n m\u00e1s precisa para comprender c\u00f3mo se comportan los NEP en el suelo ser\u00eda, marcarlos individualmente y en grandes cantidades para rastrearlas en tiempo real. El marcaje NEP nos permitir\u00e1 extraerlos directamente del suelo y contarlos bajo cualquier dise\u00f1o \u00f3ptico. Desafortunadamente, el \u00fanico m\u00e9todo disponible para marcar nematodos hasta el momento se basa en la inserci\u00f3n de prote\u00ednas fluorescentes, que son costosas, consumen mucho tiempo e imposibles de aplicar a grandes lotes de nematodos (decenas de millones). Esta situaci\u00f3n puede ser revertida con el uso de puntos cu\u00e1nticos de carbono (C-dots),ya que son baratos de producir, fluorescentes, no t\u00f3xicos y listos para usar en grandes lotes de NEP. El objetivo de este proyecto es desarrollar tecnolog\u00edas de marcaje de NEP con c-dots para poder mejorar su actividad en condiciones de campo.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2022 - Noviembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26070\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Experiencias docentes y de gesti\u00f3n para el mejoramiento educativo en contexto rural: el aporte de las artes al fortalecimiento de los otros indicadores de calidad\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26070\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26070\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto tiene como prop\u00f3sito levantar evidencias cualitativas sobre el impacto de la educaci\u00f3n art\u00edstica en la convivencia escolar de escuelas rurales antes, durante y despu\u00e9s de la pandemia Covid-19.\r\nLa investigaci\u00f3n es de \u00edndole cualitativa puesto que se han dise\u00f1ado instrumentos como entrevistas en profundidad, grupos focales con docentes y estudiantes y metodolog\u00edas art\u00edsticas como collage.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2022 - Abril 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26415\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Efecto de la obesidad inducida por el consumo de una dieta alta en grasas sobre la activaci\u00f3n del inflamamos NLRP3 en la c\u00f3clea y la funci\u00f3n del sistema auditivo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26415\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26415\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]EFECTO DE LA OBESIDAD INDUCIDA POR EL CONSUMO DE UNA DIETA ALTA EN GRASAS SOBRE LA ACTIVACI\u00d3N DEL INFLAMASOMA NLRP3 EN LA C\u00d3CLEA Y LA FUNCI\u00d3N DEL SISTEMA AUDITIVO[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Patrocinante<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2022 - Abril 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26555\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Efecto de la obesidad inducida por el consumo de una dieta alta en grasas sobre la activaci\u00f3n del inflamamos NLRP3 en la c\u00f3clea y la funci\u00f3n del sistema auditivo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26555\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26555\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]EFECTO DE LA OBESIDAD INDUCIDA POR EL CONSUMO DE UNA DIETA ALTA EN GRASAS SOBRE LA ACTIVACI\u00d3N DEL INFLAMASOMA NLRP3 EN LA C\u00d3CLEA Y LA FUNCI\u00d3N DEL SISTEMA AUDITIVO[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ECOS210044<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26932\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Development of geophysical and modeling approaches to support sustainable groundwater management in semi-arid and Mediterranean areas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26932\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26932\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]North-central Chile and south-east France are facing semi-arid and Mediterranean climates, respectively. In addition to being historically exposed to water supply challenges, these regions are sensitive to climate change, which is increasing aridity. Thus, the pressure on water resources to meet domestic, agricultural and industrial demands is high and growing. As precipitation in these regions is low and highly variable, the water stored underground is a key adjustment variable to mitigate years with low precipitation. Hence, groundwater resources need to be carefully managed in order to secure water supply in the years and decades to come. To tackle this challenge, this project aims to\r\ndevelop geophysical characterization and groundwater modeling approaches to support sustainable groundwater management. The main objective of the project is to produce key information about groundwater for water resources planners in semi-arid and Mediterranean areas such as in north-central Chile and southeast France. This objective will be achieved by training students and young researchers in state-of-the-art technologies such as the Magnetic Resonance Sounding (MRS) geophysical method and the WEAP-MODFLOW integrated water resources modeling framework.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26445\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Evaluaci\u00f3n de la utilizaci\u00f3n de compost comercial como sustrato en la viverizaci\u00f3n de especies forestales nativas en las regiones de Valpara\u00edso, Metropolitana, O&#8217;Higgins y Maule\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26445\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26445\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto que aborda el uso del compost como sustrato en la viverizaci\u00f3n de especies nativas. Se particip\u00f3 en el dise\u00f1o y desarrollo de la propuesta pero finalmente se opt\u00f3 por ser prestadores de servicios, adem\u00e1s de montar los ensayos asociados al proyecto.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1220886<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2022 - Marzo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26526\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            From deterministic to Stochastic sweeping Processes\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26526\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26526\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto de investigaci\u00f3n b\u00e1sica en procesos de arrastre estoc\u00e1sticos.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2022 - Marzo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26111\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fondecyt Regular 2022\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26111\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26111\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]During the last decades, compelling evidence shows how the context in which early life takes place impinges risk or protection for later development of non-communicable chronic diseases. In this regard, impaired fetal growth, as occur in the fetal growth restriction (FGR), leads to a higher risk for later cardiovascular diseases, an effect that would be mediated by accelerated aging at molecular, structural, and functional levels. FGR remains a leading cause of perinatal morbidity and mortality, affecting ~10% of pregnancies, but ranging from 5 to 25% depending on the population surveyed, with a higher prevalence among pregnant women of low socioeconomic status. In the clinic, FGR is normally defined by a fetal weight below the 10th percentile, however, new evidence shows that impaired intrauterine growth may affect several neonates born over the 10th percentile, especially late in pregnancy, which may be missed from the perinatal survey for preventing adverse outcomes. This points out the need for further studies to improve the understanding and identification of altered fetal growth trajectories and their consequences on vascular function. \r\nStudies in the placenta show that FGR vascular dysfunction is also found at birth in chorionic and umbilical arteries. We have demonstrated the presence of functional and molecular markers (e.g. vasodilator mediators and epigenetic changes) of endothelial dysfunction in human FGR umbilical and chorionic vessels, findings that have been further confirmed by comparing systemic and umbilical arteries in guinea pigs and chicken FGR models. These traits suggest that umbilical artery endothelial cells (HUAEC), in complement with approaches in animal models, can be used as a surrogate to explore the vascular programming within the fetus, however, their translation to clinical preventive applications for promoting healthy aging deserves further studies. It worth noting that fetal reduced oxygen supply (fetal hypoxia) and altered blood flow patterns (e.g. shear stress) are key clinical markers in the FGR, independently of the constraints leading to impaired growth, and both factors exert a tight control of vascular development and function across life. However, how these key stimuli interact and impose an epigenetic program on the endothelial function remains elusive. This proposal will focus on the crosstalk between hypoxia and shear stress that results in the endothelial programming related to impaired fetal growth, and the molecular mechanisms that mediate the vascular responses to these stimuli. Furthermore, we will address if these molecular markers may allow detecting early vascular aging in FGR subjects beyond the 10th centile cutoff. We hypothesize that \u0093Impaired fetal growth conditions are associated with epigenetic programming of aging- and mechanosensing-related miRNAs and transcripts in the endothelium, which can be triggered by the confluence of altered flow patterns and hypoxia resulting in molecular and structural pro-hypertensive biomechanical vascular properties\u0094. \r\nThis hypothesis will be addressed by three General Objectives (GO) involving ex vivo, in vitro, and in vivo observational and mechanistic approaches: GO1 To demonstrate, in HUAEC, whether late FGR results in epigenetic changes related to the regulation of vascular aging and the expression of mechanosensing mechanisms involved in the endothelial-dependent relaxation, and their relationship with general prenatal parameters of vascular health. GO1 will be performed by recruiting HUAEC samples from late FGR and control pregnancies, to assess transcriptomic and DNA methylation analyses that will be crossed with prenatal clinical data. GO2 To study, in vivo, whether hypoxia and shear stress differentially regulate mechanosensing pathways involved in the endothelial-dependent relaxation and their relationship with the in vivo and ex vivo vascular properties (e.g. functional and biomechanical). GO2 will be performed in chicken embryos exposed to hypoxia and treated with agents targeting mechanosensing pathways, in which wall shear stress will be determined by Ultrasound Localization Microscopy, with complementary functional, structural, and molecular analyses. GO 3. To study, in cultured HUAEC, whether stimuli related to impaired fetal growth converge in the regulation of mechanosensing- and aging-related transcripts and miRNA, contributing to the cellular programming of endothelial dysfunction. GO3 will be performed in HUAEC exposed, in vitro, to sustained hypoxia and diverse flow patterns (shear stress), in which target DNA methylation, miRNA, transcripts, and proteins will be assessed. Our expected outcome is to improve the knowledge about the endothelial epigenetic programming after FGR in humans and enhance the characterization of the shear stress patterns and mechanisms associated with chronic fetal hypoxia. These effects will be isolated by studying, in vivo, hypoxic chicken embryos and, in vitro, cultured HUAEC exposed to FGR-like flow patterns. This project is not only relevant to uncover the developmental mechanisms that determine short- and long-term vascular dysfunction but also to open potential approaches for preventing, diagnosing, and treating FGR-pregnancies.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2022 - Marzo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26297\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Chronic kidney disease: understanding its causality in agricultural communities in Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26297\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26297\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]EL proyecto busca asociar exposiciones ambientales, alimentarias y gen\u00e9ticas con la enfermedad renal cr\u00f3nica de causa idiop\u00e1tica en la Cohorte del Maule MAUCO, Molina, Chile[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2022 - Marzo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26327\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fondecyt Regular 2022\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26327\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26327\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]During the last decades, compelling evidence shows how the context in which early life takes place impinges risk or protection for later development of non-communicable chronic diseases. In this regard, impaired fetal growth, as occur in the fetal growth restriction (FGR), leads to a higher risk for later cardiovascular diseases, an effect that would be mediated by accelerated aging at molecular, structural, and functional levels. FGR remains a leading cause of perinatal morbidity and mortality, affecting ~10% of pregnancies, but ranging from 5 to 25% depending on the population surveyed, with a higher prevalence among pregnant women of low socioeconomic status. In the clinic, FGR is normally defined by a fetal weight below the 10th percentile, however, new evidence shows that impaired intrauterine growth may affect several neonates born over the 10th percentile, especially late in pregnancy, which may be missed from the perinatal survey for preventing adverse outcomes. This points out the need for further studies to improve the understanding and identification of altered fetal growth trajectories and their consequences on vascular function. \r\nStudies in the placenta show that FGR vascular dysfunction is also found at birth in chorionic and umbilical arteries. We have demonstrated the presence of functional and molecular markers (e.g. vasodilator mediators and epigenetic changes) of endothelial dysfunction in human FGR umbilical and chorionic vessels, findings that have been further confirmed by comparing systemic and umbilical arteries in guinea pigs and chicken FGR models. These traits suggest that umbilical artery endothelial cells (HUAEC), in complement with approaches in animal models, can be used as a surrogate to explore the vascular programming within the fetus, however, their translation to clinical preventive applications for promoting healthy aging deserves further studies. It worth noting that fetal reduced oxygen supply (fetal hypoxia) and altered blood flow patterns (e.g. shear stress) are key clinical markers in the FGR, independently of the constraints leading to impaired growth, and both factors exert a tight control of vascular development and function across life. However, how these key stimuli interact and impose an epigenetic program on the endothelial function remains elusive. This proposal will focus on the crosstalk between hypoxia and shear stress that results in the endothelial programming related to impaired fetal growth, and the molecular mechanisms that mediate the vascular responses to these stimuli. Furthermore, we will address if these molecular markers may allow detecting early vascular aging in FGR subjects beyond the 10th centile cutoff. We hypothesize that \u0093Impaired fetal growth conditions are associated with epigenetic programming of aging- and mechanosensing-related miRNAs and transcripts in the endothelium, which can be triggered by the confluence of altered flow patterns and hypoxia resulting in molecular and structural pro-hypertensive biomechanical vascular properties\u0094. \r\nThis hypothesis will be addressed by three General Objectives (GO) involving ex vivo, in vitro, and in vivo observational and mechanistic approaches: GO1 To demonstrate, in HUAEC, whether late FGR results in epigenetic changes related to the regulation of vascular aging and the expression of mechanosensing mechanisms involved in the endothelial-dependent relaxation, and their relationship with general prenatal parameters of vascular health. GO1 will be performed by recruiting HUAEC samples from late FGR and control pregnancies, to assess transcriptomic and DNA methylation analyses that will be crossed with prenatal clinical data. GO2 To study, in vivo, whether hypoxia and shear stress differentially regulate mechanosensing pathways involved in the endothelial-dependent relaxation and their relationship with the in vivo and ex vivo vascular properties (e.g. functional and biomechanical). GO2 will be performed in chicken embryos exposed to hypoxia and treated with agents targeting mechanosensing pathways, in which wall shear stress will be determined by Ultrasound Localization Microscopy, with complementary functional, structural, and molecular analyses. GO 3. To study, in cultured HUAEC, whether stimuli related to impaired fetal growth converge in the regulation of mechanosensing- and aging-related transcripts and miRNA, contributing to the cellular programming of endothelial dysfunction. GO3 will be performed in HUAEC exposed, in vitro, to sustained hypoxia and diverse flow patterns (shear stress), in which target DNA methylation, miRNA, transcripts, and proteins will be assessed. Our expected outcome is to improve the knowledge about the endothelial epigenetic programming after FGR in humans and enhance the characterization of the shear stress patterns and mechanisms associated with chronic fetal hypoxia. These effects will be isolated by studying, in vivo, hypoxic chicken embryos and, in vitro, cultured HUAEC exposed to FGR-like flow patterns. This project is not only relevant to uncover the developmental mechanisms that determine short- and long-term vascular dysfunction but also to open potential approaches for preventing, diagnosing, and treating FGR-pregnancies.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2022 - Mayo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26478\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            NetForSur: Assessing Andean forest vulnerability under climate change: a dendroecological, ecophysiological and biogeographic approach\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26478\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26478\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The NetForSur project will evaluate the vulnerability of forests to climate change along a latitudinal gradient in the Andes Cordillera; to achieve this goal, we will build a research network including 4 countries (Argentina, Chile, France, Peru) to develop synergies using similar methodologies in dendroecology, ecophysiology and remote sensing. The results will complete worldwide inventories of forest dieback and to propose updating of the species status in national and international red lists.\r\n\r\nObj 1 : We will assess the level of forest decline and tree mortality in the Andes Cordillera, through a bibliographic analysis including published and grey literature, since many studies are not yet available in international literature or only in Spanish. We will seek to identify the species at stake, the significance of decline in symptoms and surface area affected, the abiotic events associated to the decline and the mechanisms underlying the observed decline.\r\n\r\nObj 2: The growth dynamics of endangered, declining or protected tree species will be\r\nanalyzed. We will use a common methodology to study tree growth response to climate change, building a database to share existing data in dendro-ecology and field stand monitoring over the whole latitudinal gradient, and over local environmental gradients. We will explore several remote sensing tools to upscale the analyses at landscape and regional.\r\n\r\nObj 3: Our third objective is to evaluate the ecophysiological adaptive strategies to climate change of endangered or declining tree species (Araucaria araucana, Austrocedrus chilensis, Nothofagus spp, Polylepis spp.). We will set up a common methodology to study tree\r\necophysiology, measuring adaptive traits characteristic of plant response to abiotic stress (hydraulic traits, energy dissipation traits) associating lab-measured species-specific traits and\r\nfield based ecophysiological campaigns.\r\n\r\nObj 4: Tree mortality risk will be assessed using model simulations associated to current\r\nand future climatic conditions using the SUREAU ecophysiological model. It will be adapted\r\nto local species and environmental conditions of the Andean Cordillera, and parameterized using data from objectives 2 and 3. Mortality risks predicted by the model will be evaluated in front of decline estimated in the field. Model simulations will be further considered under climate change scenario.\r\n\r\nObj 5: A major goal will be to build a long-term research network on forest adaptation to climate change. The collaboration, data sharing and methodology integration will focus on strengthening the international network between all countries in a formalized framework such as 2RI (https:\/\/www.inrae.fr\/en\/2ri-international-research-networks), and to visualize other calls in conjunction with the project to develop and disseminate new joint results on the adaptation of forests to climate change.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1220797<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2022 - Marzo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26539\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Inhibici\u00f3n y generalizaci\u00f3n del miedo aprendido como indicadores de vulnerabilidad para el desarrollo de ansiedad.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26539\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26539\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En el emergente campo de investigaci\u00f3n sobre la identificaci\u00f3n de factores de vulnerabilidad para el\r\ndesarrollo de patolog\u00eda ansiosa, destaca la incorporaci\u00f3n de los procesos de generalizaci\u00f3n del miedo\r\ncondicionado. La generalizaci\u00f3n es una caracter\u00edstica de las personas ansiosas, en tanto el foco del miedo se\r\nvuelve excesivo y se extiende a situaciones que no son amenazantes (i.e. sobregeneralizaci\u00f3n). As\u00ed,\r\nvariaciones individuales en el proceso de generalizaci\u00f3n explicar\u00edan estos resultados, Alternativamente, se\r\nha propuesto a un fallo en la inhibici\u00f3n del miedo como mecanismo para explicar la sobregeneralizaci\u00f3n.\r\nTan importante como aprender a temer a una amenaza, es aprender a no tener miedo ante se\u00f1ales de\r\nseguridad (i.e., inhibir). Un n\u00famero de experimentos ha demostrado evidencia sugerente, pero no sustantiva,\r\nde propiedades inhibitorias de se\u00f1ales de seguridad en la generalizaci\u00f3n del miedo en humanos.\r\nLos estudios de miedo condicionado, que incluyen medidas de generalizaci\u00f3n o inhibici\u00f3n, t\u00edpicamente por\r\nseparado, proveen un modelo traslacional completo de la ansiedad, abarcando desde su etiolog\u00eda hasta las\r\nreca\u00eddas luego del tratamiento, permitiendo una comprensi\u00f3n te\u00f3rica de sus mecanismos subyacentes, y\r\nuna contribuci\u00f3n pr\u00e1ctica en la identificaci\u00f3n de par\u00e1metros para mejorar el tratamiento -basado en la\r\nextinci\u00f3n- y reducir as\u00ed las reca\u00eddas. En base a esta relevancia traslacional, es necesario estudiar las\r\ndiferencias individuales en mecanismos de aprendizaje y su relaci\u00f3n con la vulnerabilidad para el desarrollo\r\nde la ansiedad (vulnerabilidad ansiosa). En particular, el presente proyecto se interesa en dos procesos:\r\ngeneralizaci\u00f3n e inhibici\u00f3n del miedo.\r\nEn la literatura actual, existen cuatro problemas importantes respecto a la evaluaci\u00f3n de mecanismos\r\ninhibitorios y de la generalizaci\u00f3n como procesos alternativos para explicar las respuestas excesivas de\r\nmiedo. 1) Los estudios no incluyen medidas tradicionales de inhibici\u00f3n. 2) No se ha caracterizado el tipo de\r\nproceso inhibitorio que participar\u00eda en la sobregeneralizaci\u00f3n. 3) El tercer problema es de \u00edndole te\u00f3rico:\r\nexiste la posibilidad de que la inhibici\u00f3n sea parte del proceso de generalizaci\u00f3n (Spence, 1936). Desde\r\nesta teor\u00eda, no es necesario proponer a la inhibici\u00f3n como alternativa a la generalizaci\u00f3n del miedo en\r\nhumanos, en tanto los dos procesos por separado amenazan la parsimonia. La idea b\u00e1sica es que, al\r\nestablecer discriminaciones -lo opuesto a generalizar- entre se\u00f1ales de amenaza y de seguridad, los\r\nsujetos aprenden ambas. De la primera, las calves de amenaza, aprenden una tendencia excitatoria,\r\nmientras que, de las se\u00f1ales de seguridad, se adquiere un aprendizaje de tipo inhibitorio. Tambi\u00e9n, las\r\nevaluaciones de esta cuesti\u00f3n en la literatura son insuficientes, no existiendo estudios con mediciones\r\nindependientes de la generalizaciestim\u00f3n e inhibici\u00f3n. 4) Tampoco existen estudios sistem\u00e1ticos que\r\neval\u00faen los procesos de generalizaci\u00f3n e inhibici\u00f3n luego de la adquisici\u00f3n, extinci\u00f3n y situaciones de\r\nreca\u00eddas. Cada una de estas etapas tiene importancia traslacional en tanto modelan la etiolog\u00eda, el\r\ntratamiento y la potencial reca\u00edda despu\u00e9s del tratamiento en trastornos de ansiedad.\r\nFrente a esta problem\u00e1tica, nos preguntamos si en el aprendizaje discriminativo de miedo en la poblaci\u00f3n\r\nadulta \u00bfla generalizaci\u00f3n y la inhibici\u00f3n contribuyen, de manera separada o como un \u00fanico mecanismo, en\r\nlas distintas etapas (adquisici\u00f3n, extinci\u00f3n y reca\u00eddas)? \u00bfCu\u00e1l es la relaci\u00f3n que tienen estos mecanismos\r\ncon la vulnerabilidad ansiosa? Para responder a esta pregunta dise\u00f1amos 3 l\u00edneas de experimentos. En la\r\nl\u00ednea 1 buscamos determinar si manipulaciones que afectan la inhibici\u00f3n producen un efecto sobre la\r\ngeneralizaci\u00f3n. En la l\u00ednea 2 buscamos determinar si manipulaciones que afectan la generalizaci\u00f3n\r\nproducen un efecto sobre la inhibici\u00f3n. En la l\u00ednea 3 buscamos determinar si manipulaciones que afectan\r\nla inhibici\u00f3n y la generalizaci\u00f3n interact\u00faan en sus efectos de generalizaci\u00f3n e inhibitorios. En cada\r\nexperimento, las manipulaciones son tratadas como variables independientes que generan distintos\r\ngrupos. Los participantes proveer\u00e1n respuestas en m\u00faltiples medidas de inhibici\u00f3n y generalizaci\u00f3n en las\r\ndistintas fases de adquisici\u00f3n, extinci\u00f3n y reca\u00edda luego de la extinci\u00f3n. Antes de comenzar el experimento,\r\nlos participantes proveen respuestas de cuestionarios para evaluar la vulnerabilidad ansiosa. Estos datos\r\npermitir\u00e1n evaluar la relaci\u00f3n que tienen los efectos inhibitorios y de generalizaci\u00f3n con la vulnerabilidad\r\nansiosa. Se espera que 1) los resultados apoyen la teor\u00eda de Spence y 2) que se observe m\u00e1s\r\ngeneralizaci\u00f3n y menos inhibici\u00f3n en sujetos m\u00e1s ansiosos. Este \u00faltimo resultado ser\u00eda evidencia a favor de\r\nque esta variaci\u00f3n en los mecanismos de aprendizaje contribuir\u00eda a la vulnerabilidad para el desarrollo de\r\nsintomatolog\u00eda ansiosa.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2022 - Abril 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26571\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Una aproximaci\u00f3n gradual para el desarrollo y an\u00e1lisis del conocimiento especializado de la estoc\u00e1stica en futuros profesores chilenos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26571\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26571\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La estoc\u00e1stica (entendida como la uni\u00f3n entre la estad\u00edstica y probabilidad) se ha establecido como un\r\ncomponente necesario para desenvolverse eficazmente en la era de la informaci\u00f3n. Esta situaci\u00f3n, ha\r\ngenerado un movimiento de reforma curricular en torno a su ense\u00f1anza en la escuela, a la que se han\r\nsumado un gran n\u00famero de pa\u00edses. En este contexto, el \u00e9xito de las nuevas directrices curriculares depende\r\nfuertemente de la formaci\u00f3n de quienes tienen la tarea de su implementaci\u00f3n, los profesores de matem\u00e1tica.\r\nCon ello, emerge el problema de que muchos docentes consideran que no est\u00e1n bien preparados para\r\nense\u00f1ar estad\u00edstica ni para afrontar las dificultades de sus estudiantes. En consecuencia, nos planteamos\r\nque las mayores problem\u00e1ticas relativas al conocimiento del contenido y la ense\u00f1anza de la estoc\u00e1stica en\r\nprofesores pueden ser abordadas reorientando su formaci\u00f3n inicial. En esta nueva mirada, es necesario\r\nconsiderar el desarrollo de habilidades vinculadas con las tareas profesionales del estad\u00edstico y con un fuerte\r\napoyo tecnol\u00f3gico. Esta perspectiva se ha sintetizado en nuevos curr\u00edculos centrados en la inferencia a trav\u00e9s\r\nde la simulaci\u00f3n computacional (SBI por Simulation-Based introduction to Inference) basadas en t\u00e9cnicas de\r\nre-muestreo (repeated sampling), procedimientos que consideran la repetici\u00f3n reiterada de los procesos de\r\nmuestreo.\r\n\r\nObjetivos\r\nAsumiendo el modelo de Conocimiento did\u00e1ctico-matem\u00e1ticos del profesor como marco te\u00f3rico de esta\r\ninvestigaci\u00f3n, nos planteamos analizar el desarrollo de los conocimientos did\u00e1ctico-matem\u00e1ticos de los\r\nfuturos profesores de educaci\u00f3n media en relaci\u00f3n a la ense\u00f1anza de la estoc\u00e1stica a trav\u00e9s de enfoques\r\nprogresivos de lo informal a lo formal. Meta que se articula en torno a cinco metas parciales relativas a: (1)\r\nAnalizar la pertinencia y adecuaci\u00f3n de centrar el curr\u00edculo de estoc\u00e1stica en la inferencia, basados en la\r\nsimulaci\u00f3n computacional; (2) Dise\u00f1ar m\u00f3dulos de ense\u00f1anza para introducir progresivamente las ideas\r\nclaves en la formaci\u00f3n del profesorado; (3) Explorar los resultados de la implementaci\u00f3n de los m\u00f3dulos\r\ndise\u00f1ados en futuros profesores de matem\u00e1tica; (4) Explorar los conocimientos meta-did\u00e1cticos de los\r\nfuturos profesores al valorar la idoneidad did\u00e1ctica de algunas secuencias dise\u00f1adas para ser utilizadas en el\r\n\u00e1mbito escolar; (5) Analizar los conocimientos did\u00e1ctico-matem\u00e1ticos sobre la estoc\u00e1stica en los futuros\r\nprofesores de matem\u00e1tica durante una asignatura de ense\u00f1anza de la estoc\u00e1stica[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1220797<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2022 - Marzo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26722\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Inhibici\u00f3n y generalizaci\u00f3n del miedo aprendido como indicadores de vulnerabilidad para el desarrollo de ansiedad.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26722\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26722\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En el emergente campo de investigaci\u00f3n sobre la identificaci\u00f3n de factores de vulnerabilidad para el\r\ndesarrollo de patolog\u00eda ansiosa, destaca la incorporaci\u00f3n de los procesos de generalizaci\u00f3n del miedo\r\ncondicionado. La generalizaci\u00f3n es una caracter\u00edstica de las personas ansiosas, en tanto el foco del miedo se\r\nvuelve excesivo y se extiende a situaciones que no son amenazantes (i.e. sobregeneralizaci\u00f3n). As\u00ed,\r\nvariaciones individuales en el proceso de generalizaci\u00f3n explicar\u00edan estos resultados, Alternativamente, se\r\nha propuesto a un fallo en la inhibici\u00f3n del miedo como mecanismo para explicar la sobregeneralizaci\u00f3n.\r\nTan importante como aprender a temer a una amenaza, es aprender a no tener miedo ante se\u00f1ales de\r\nseguridad (i.e., inhibir). Un n\u00famero de experimentos ha demostrado evidencia sugerente, pero no sustantiva,\r\nde propiedades inhibitorias de se\u00f1ales de seguridad en la generalizaci\u00f3n del miedo en humanos.\r\nLos estudios de miedo condicionado, que incluyen medidas de generalizaci\u00f3n o inhibici\u00f3n, t\u00edpicamente por\r\nseparado, proveen un modelo traslacional completo de la ansiedad, abarcando desde su etiolog\u00eda hasta las\r\nreca\u00eddas luego del tratamiento, permitiendo una comprensi\u00f3n te\u00f3rica de sus mecanismos subyacentes, y\r\nuna contribuci\u00f3n pr\u00e1ctica en la identificaci\u00f3n de par\u00e1metros para mejorar el tratamiento -basado en la\r\nextinci\u00f3n- y reducir as\u00ed las reca\u00eddas. En base a esta relevancia traslacional, es necesario estudiar las\r\ndiferencias individuales en mecanismos de aprendizaje y su relaci\u00f3n con la vulnerabilidad para el desarrollo\r\nde la ansiedad (vulnerabilidad ansiosa). En particular, el presente proyecto se interesa en dos procesos:\r\ngeneralizaci\u00f3n e inhibici\u00f3n del miedo.\r\nEn la literatura actual, existen cuatro problemas importantes respecto a la evaluaci\u00f3n de mecanismos\r\ninhibitorios y de la generalizaci\u00f3n como procesos alternativos para explicar las respuestas excesivas de\r\nmiedo. 1) Los estudios no incluyen medidas tradicionales de inhibici\u00f3n. 2) No se ha caracterizado el tipo de\r\nproceso inhibitorio que participar\u00eda en la sobregeneralizaci\u00f3n. 3) El tercer problema es de \u00edndole te\u00f3rico:\r\nexiste la posibilidad de que la inhibici\u00f3n sea parte del proceso de generalizaci\u00f3n (Spence, 1936). Desde\r\nesta teor\u00eda, no es necesario proponer a la inhibici\u00f3n como alternativa a la generalizaci\u00f3n del miedo en\r\nhumanos, en tanto los dos procesos por separado amenazan la parsimonia. La idea b\u00e1sica es que, al\r\nestablecer discriminaciones -lo opuesto a generalizar- entre se\u00f1ales de amenaza y de seguridad, los\r\nsujetos aprenden ambas. De la primera, las calves de amenaza, aprenden una tendencia excitatoria,\r\nmientras que, de las se\u00f1ales de seguridad, se adquiere un aprendizaje de tipo inhibitorio. Tambi\u00e9n, las\r\nevaluaciones de esta cuesti\u00f3n en la literatura son insuficientes, no existiendo estudios con mediciones\r\nindependientes de la generalizaciestim\u00f3n e inhibici\u00f3n. 4) Tampoco existen estudios sistem\u00e1ticos que\r\neval\u00faen los procesos de generalizaci\u00f3n e inhibici\u00f3n luego de la adquisici\u00f3n, extinci\u00f3n y situaciones de\r\nreca\u00eddas. Cada una de estas etapas tiene importancia traslacional en tanto modelan la etiolog\u00eda, el\r\ntratamiento y la potencial reca\u00edda despu\u00e9s del tratamiento en trastornos de ansiedad.\r\nFrente a esta problem\u00e1tica, nos preguntamos si en el aprendizaje discriminativo de miedo en la poblaci\u00f3n\r\nadulta \u00bfla generalizaci\u00f3n y la inhibici\u00f3n contribuyen, de manera separada o como un \u00fanico mecanismo, en\r\nlas distintas etapas (adquisici\u00f3n, extinci\u00f3n y reca\u00eddas)? \u00bfCu\u00e1l es la relaci\u00f3n que tienen estos mecanismos\r\ncon la vulnerabilidad ansiosa? Para responder a esta pregunta dise\u00f1amos 3 l\u00edneas de experimentos. En la\r\nl\u00ednea 1 buscamos determinar si manipulaciones que afectan la inhibici\u00f3n producen un efecto sobre la\r\ngeneralizaci\u00f3n. En la l\u00ednea 2 buscamos determinar si manipulaciones que afectan la generalizaci\u00f3n\r\nproducen un efecto sobre la inhibici\u00f3n. En la l\u00ednea 3 buscamos determinar si manipulaciones que afectan\r\nla inhibici\u00f3n y la generalizaci\u00f3n interact\u00faan en sus efectos de generalizaci\u00f3n e inhibitorios. En cada\r\nexperimento, las manipulaciones son tratadas como variables independientes que generan distintos\r\ngrupos. Los participantes proveer\u00e1n respuestas en m\u00faltiples medidas de inhibici\u00f3n y generalizaci\u00f3n en las\r\ndistintas fases de adquisici\u00f3n, extinci\u00f3n y reca\u00edda luego de la extinci\u00f3n. Antes de comenzar el experimento,\r\nlos participantes proveen respuestas de cuestionarios para evaluar la vulnerabilidad ansiosa. Estos datos\r\npermitir\u00e1n evaluar la relaci\u00f3n que tienen los efectos inhibitorios y de generalizaci\u00f3n con la vulnerabilidad\r\nansiosa. Se espera que 1) los resultados apoyen la teor\u00eda de Spence y 2) que se observe m\u00e1s\r\ngeneralizaci\u00f3n y menos inhibici\u00f3n en sujetos m\u00e1s ansiosos. Este \u00faltimo resultado ser\u00eda evidencia a favor de\r\nque esta variaci\u00f3n en los mecanismos de aprendizaje contribuir\u00eda a la vulnerabilidad para el desarrollo de\r\nsintomatolog\u00eda ansiosa.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> BPVE-00066\/22<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2022 - Abril 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>FAPEMA<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27001\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27001\" aria-expanded=\"false\" aria-controls=\"collapse-27001\">\n                                            Impacto da fertirriga\u00e7\u00e3o com sil\u00edcio e da inocula\u00e7\u00e3o com Azospirillum brasilense sobre os par\u00e2metros ecofisiol\u00f3gicos, nutricionais, produtivos e da qualidade da silagem de milho safrinha para alimenta\u00e7\u00e3o animal no estado do Maranh\u00e3o\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27001\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27001\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1220058<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27071\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            UNDERSTANDING THE STRUCTURE-PROPERTY RELATIONSHIPS ON ADVANCED HIGH STRENGTH STEELS OBTAINED VIA CHEMICAL PATTERNING OF AUSTENITE\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27071\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27071\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Society is facing an unprecedented challenge in terms of combining sustainability, economic growth and\r\ntechnological development. The industry has tackled these demands by developing novel products and\r\ninnovative service strategies, taking the maximum advantage of the installed capabilities and cutting edge\r\ntechnologies. Steel industry has taken the lead by supporting internal research and scientific collaborations\r\nworldwide, enabling an ever increasing number of scientific developments. Steel plays a major role as the\r\nbackbone material of civilization for a number of reasons, namely (i) abundance, (ii) relatively cheap, (iii)\r\nwide range of properties and applications, (iv) 100% recyclable, (v) potential to improve in-service\r\nperformance.\r\nIn the framework of (v), the current proposal aims to provide new grades of steel by means of chemical\r\npatterning of austenite. The concept of austenite patterning consists in producing layers in the microstructure\r\nwith a chemical composition different from the bulk composition, via specific alloying elements and thermal\r\ncycles. These layers, after fully austenitization, deliver transformation products on cooling different than\r\nexpected from the average austenite, allowing a new degree of freedom for tailoring of microstructures. So\r\nfar there is only one scientific paper on the subject, which has reported outstanding mechanical strength\r\n(ultimate) of ca. 2 GPa, with uniform elongations of 7% in a lamellar martensite-austenite microstructure in\r\na single 0.51C-4.35Mn steel.\r\nThe present proposal sets a detailed working plan to investigate the impact of the initial microstructure and\r\nthermal path upon the chemical patterning of austenite in a number of different steel chemistries. The aim\r\nis two-folded: to analize the evolution of the phase transformations at different stages of the process as a\r\nfunction of the initial microstructure and heat-treatment parameters, and to gain fundamental insights on\r\nthe mechanical behavior of the new steel grades. It is hypothesized that the correct interplay of the\r\nparameters mentioned above can yield optimized final microstructures with enhanced in-service\r\nperformance.The methodology incorporates up-to-date assessment tools of thermodynamic equilibria and\r\nkinetics (ThermoCalc & Dictra) in selected steel chemistries, accurate tracking of phase transformations via\r\nDilatometry experiments, in-depth characterization of the microstructure and mechanical properties and insitu\/ex-situ ultrasound probing of tensile test specimens to better understand the hardening mechanisms.\r\nThe experimental results will be compared with modeling strategies for both phase transformations and\r\nmechanical behavior.\r\nThe expected results of the proposal will be of interest to the scientific community due to the novelty of the\r\nexperimental concept and the potential contribution to the understanding of structure-property relations.\r\nElse, the findings will be of significance for the design of structural parts, such as high strength and impact\r\ntoughness for car body crash worthiness. In the case of Chilean mining industry, wear and impact wear\r\nresistance are potential applications of the new steel grades to be tested. The proposal is lay out within a\r\nnovel cooperation framework between a group of specialists on specific aspects of materials science (phase\r\ntransformations in steel, constitutive modeling, ultrasound probing), oriented to contribute to the\r\nfundamental understanding of the microstructure-property relations resulting from chemical patterning of\r\naustenite. Additionally, three universities and one industrial partner (University of Twente, The Nederland,\r\nGent University, Belgium; University of Alberta, Canada; and ME Elecmetal, Chile-US, respectively) are\r\nsupporting the proposal with resources such as workshops, sample preparation, specific characterization\r\ntechniques, software for post-processing, among others.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11221052:<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Marzo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27115\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            \u00bfPeligro para la seguridad de la sociedad?: Una investigaci\u00f3n sobre la determinaci\u00f3n de la peligrosidad en el uso de prisi\u00f3n preventiva\u0094.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27115\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27115\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En el fallo de la Corte Interamericana de Derechos Humanos \u0093Norin Catriman v. Chile\u0094, la Corte reconoci\u00f3 que\r\nla causal para imponer la medida de prisi\u00f3n preventiva basada en \u0093peligro para la seguridad de la sociedad\u0094\r\nera de car\u00e1cter abierto y podr\u00eda ser utilizada de manera contraria a la convenci\u00f3n americana. La \u00fanica\r\nmanera, por tanto, de utilizar la causal es que esta se funde en criterios que est\u00e9n dirigidos a cautelar un fin\r\nprocesal que deba ser resguardado en un caso concreto de manera excepcional. Esta postura ha sido\r\nadoptada por diversos autores nacionales (Hadwa, 2020, Correa 2017, Correa y Winter, 2014, Duce y Riego,\r\n2011). Sin embargo, varios estudios (Morales et al, 2011; Morgado, 2018; Hadwa, 2020) sugieren que en la\r\npr\u00e1ctica los jueces estar\u00edan dotando de contenido a la causal \u0093peligro para la seguridad de la sociedad\u0094\r\n\u00fanicamente evaluando la existencia de uno o m\u00e1s de los elementos contemplados en los incisos tercero y\r\ncuarto del art\u00edculo 140. En otras palabras, no se estar\u00edan cumpliendo con los requisitos establecidos por la\r\nCIDH y por fallos de la misma Corte Suprema Chilena (CS 192-09; 5437-12;6659-15; 40.862-17) que ha\r\nfallado que los criterios de dichos incisos son orientadores y no son suficientes para fundar una prisi\u00f3n\r\npreventiva. Sin embargo, Correa y Winter (2013\/2014) plantean que, en casos de delitos econ\u00f3micos que tengan alta\r\nconnotaci\u00f3n p\u00fablica, se producir\u00eda un cambio en la racionalidad \u0093habitual\u0094 de algunos jueces. Las sentencias que estos\r\nautores comentan permitir\u00edan constatar que, al menos en algunas decisiones, el inter\u00e9s medi\u00e1tico afectar\u00eda las\r\nracionalidades detr\u00e1s de la imposici\u00f3n de la prisi\u00f3n preventiva. Estos estudios contradicen la explicaci\u00f3n que\r\nmencion\u00e1ramos m\u00e1s arriba y por tanto simplemente refuerza a\u00fan m\u00e1s la necesidad de explorar la operacionalizaci\u00f3n de\r\nesta causal en la pr\u00e1ctica legal en Chile.\r\nHip\u00f3tesis a corroborar o falsear: Los jueces de garant\u00eda est\u00e1n aplicando la causal de \u0093peligro para la\r\nsociedad\u0094 de manera normativa, utilizando \u00fanicamente los criterios del inciso tercero y cuarto del art\u00edculo 140\r\ny para fundamentar la imposici\u00f3n de prisi\u00f3n preventiva. El objetivo general: Analizar el uso del concepto de\r\n\u0093peligro de seguridad para la sociedad\u0094 durante las audiencias de prisi\u00f3n preventiva, por parte de los actores\r\npenales (jueces, fiscales y defensores) en una muestra de tribunales de las regiones del Biob\u00edo y la\r\nAraucan\u00eda.\r\nObjetivo espec\u00edfico 1: Describir la operacionalizaci\u00f3n los actores penales hacen del concepto de \u0093peligro\r\npara la seguridad de la sociedad\u0094. (Observaci\u00f3n de audiencias y registro de audiencias; entrevistas\r\nsemiestructuradas con actores involucrados) Objetivo espec\u00edfico 2: Describir la conceptualizaci\u00f3n que los\r\nactores penales realizan de sujeto \u0093peligroso\u0094 en el contexto de las discusiones sobre la causal de \u0093peligro\r\npara la seguridad de la sociedad\u0094. (Observaci\u00f3n de audiencias y registro de audiencias; entrevistas\r\nsemiestructuradas con actores involucrados) Objetivo espec\u00edfico 3: Describir como los actores penales\r\nexplican sus pr\u00e1cticas en torno a la operacionalizaci\u00f3n y conceptualizaci\u00f3n del t\u00e9rmino peligro para la\r\nsociedad\u0094. (Entrevistas semiestructuradas con actores involucrados) Objetivo espec\u00edfico 4: Analizar la\r\nfundamentaci\u00f3n de las decisiones de prisi\u00f3n preventiva en las resoluciones que se dicten. (estudio documental\r\nde jurisprudencia) Objetivo espec\u00edfico 5: Comparar la operacionalizaci\u00f3n, explicaci\u00f3n del concepto entre los\r\ndistintos actores penales (jueces, fiscales y defensores). (Observaci\u00f3n de audiencias y registro de audiencias;\r\nentrevistas semiestructuradas con actores involucrados; estudio de jurisprudencia)\r\nMetodolog\u00eda: Se utilizar\u00e1n m\u00e9todos mixtos involucrando: Primero una observaci\u00f3n no participante de 3\r\ntribunales en cada una de las 2 regiones en que se enfocar\u00e1 esta investigaci\u00f3n (6 en total). Este trabajo de\r\ncampo durar\u00e1 entre 2 a 3 meses por tribunal. Se centrar\u00e1 en las audiencias de control de detenci\u00f3n y\r\naudiencias programadas que se fijen para discutir medidas cautelares. Segundo: Entrevistas semi\r\nestructuradas a actores penales (jueces, fiscales y defensores) sobre conceptualizaci\u00f3n de la peligrosidad\r\nvinculada al art\u00edculo 140 y sus pr\u00e1cticas. Tercero: Un estudio documental de la jurisprudencia de los\r\ntribunales que se observar\u00e1n, de manera de contrastar la observaci\u00f3n con sus registros y evaluar las\r\nfundamentaciones de las causales. Resultados esperados: Se espera poder describir la realidad pr\u00e1ctica del\r\nuso de la prisi\u00f3n preventiva, y en particular, de la causal \u0093peligro para la seguridad de la sociedad\u0094 en las\r\njurisdicciones observadas. Con estos datos se busca enriquecer el debate sobre el uso de la prisi\u00f3n preventiva\r\nen Chile con datos obtenidos de los mismos actores que la utilizan a diario.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11220777<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Marzo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27045\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Structural control on residence times and metal sources in geothermal waters from Southern Andes: implications for geothermal systems and epithermal deposits formation\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27045\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27045\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Ensure a secure and sustainable energy and mineral supply is a major challenge for the 21th century. Understanding the nature and evolution of hydrothermal systems can contribute to that aim by improving the effectiveness of exploration strategies for geothermal energy and precious metal epithermal deposits. Studies bridging together geochemistry and structural geology have shown that fault activity plays a critical role on fluid circulation and fluid chemical composition in hydrothermal systems. Despite the relevance of processes affecting the chemical and physical dimensions in such dynamic systems, little is known about the residence times of fluids and its metal budget in different structural contexts.\r\nInto this framework, fundamental questions arise regarding the optimal conditions leading to the development of high enthalpy geothermal resources and the formation of epithermal deposits: What is the structural control on the sources and concentration of base metals in hydrothermal fluids? How does the structural context affect the water residence times in hydrothermal systems? How does the meteoric recharge affect the geothermal systems in different structural domains?\r\nAn ideal natural laboratory to address these questions is the Andean Cordillera of Central-Southern Chile, where hydrothermal systems occur in close spatial relationship with active volcanism as well as major seismically-active fault systems. Recent studies based on fluid geochemistry and noble gases isotopic composition have shown that the intersection of structural features promotes both the accumulation formation of magmatic\/hydrothermal reservoir in the upper crust exerting a first-order control on hydrothermal fluid composition by conditioning residence times of magmas, promoting magma differentiation and separation of magmatic vapors. However, how similar processes are involved on residence times and metal budget of hydrothermal fluids remains unconstrained.\r\nWe propose a geochemical and multi-isotopic study that integrates state-of-the-art analytical techniques to unravel the circulation times and base metals contribution from magma degassing and water- rock interaction in two volcano-tectonic settings in Southern Andes, i) the arc parallel strike-slip Liqui\u00f1e- Ofqui Fault System (LOFS) and ii) the intersection between the LOFS structures and the Andean Transverse Fault (ATF). I will integrate major and trace elements (e.g., Cu, Pb, Zn, among others) geochemistry of hot springs with water dating systems (3H-3He, 14C, U-Th\/4He), noble gas (3He\/4He; 40Ar\/36Ar, 4He\/20Ne), strontium (87Sr\/86Sr) and water stable (&#120575;!\"&#119874;, &#120575; #&#119867;) isotopes to identify the circulation times, recharge condition and metal budget of hydrothermal systems.\r\nThis study will be the first to directly measure the residence times and metals contents of hydrothermal fluids in the Southern Andes of Chile. The results from the study will contribute to a better understanding of the fundamental geological and environmental controls on the evolution of hydrothermal systems. The data will directly impact the community exploring for geothermal energy in the Andes because it will help them to better constrain the formation and recharge times of geothermal reservoirs. In addition, this will be an original contribution that will impact the general geochemical science community, as no data exists on the links between residence times of hydrothermal fluids and the structural context.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Marzo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26135\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Role of specialized pro-resolving mediators on inflammation, cardiometabolic health, disease progression, and quality of life in patients with rheumatoid arthritis after omega-3 PUFA supplementation and aerobic exercise training\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26135\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26135\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto que busca determinar mecanismos moleculares de como los \u00e1cidos grasos omega-3 y el ejercicio f\u00edsico pueden mejorar la calidad de vida, funcionalidad y par\u00e1metros de inflamaci\u00f3n de pacientes con artritis reumatoide.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Marzo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26342\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Thermal variability of the root-to-canopy system in European plum: Effect on the Non-Structural Carbohydrates (NSC) metabolism and its relationship with phenological pattern\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26342\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26342\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]To determine the changes on the root-to-canopy system temperatura gradient and their effect of NSC concentration and allocations on different European plum tree organs and tissue, and to establish their relationship with phenology stages undes a scenario the climate change[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> Fondecyt Iniciaci\u00f3n 11221230<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Marzo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26467\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            ADVANCES ON STOCHASTIC MODEL PREDICTIVE CONTROL BASED ON FUZZY AND NEURAL MODELS\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26467\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26467\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]This project will consider the design of Stochastic MPC strategies based Computational Intelligence techniques such as fuzzy models and neural networks, but focusing on achieving theoretical properties such as stability and feasibility, increasing computation speed, and can use control policies. This is novel in that these properties are hardly ever obtained when using nonlinear models in SMPC. Additionally, we will aim to systematize the stability and convergence analyses. These developments will be validated on applications such as irrigation systems, climatization systems, microgrids. This is expected to improve the performance of existing control methods for systems with stochastic uncertainty, and enable the design of advanced control systems where the lack of guarantees or slow computation does not permit the implementation of advanced control systems.\r\nAdditionally, the development of ad-hoc controllers based on SMPC with RL for Electric Vehicle Routing will be tackled in this research. This controller will be tackled following principles particularly selected for this application since stability is not a major concern here because of the finite horizon for every day of operation.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FONDECYT 11220989<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Marzo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26590\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Cyber-attacks in modular multilevel conververts (MMCs)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26590\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26590\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]PROPOSAL ABSTRACT: Cyber-attacks in modular multilevel converters (MMCs)\r\n     Cyber-attacks on electrical systems are a major concern to many countries as they can have significant impacts on social well-being and economic prosperity. Recent examples of such attacks are (i) the cyber-attacks that targeted the supervisory control data acquisition (SCADA) system of the Ukrainian power grid, causing a power outage that affected approximately 225,000 customers, (ii) the cyber-attack that occurred in 2019 in Venezuela, affecting the power supply of Caracas city, and (iii) the cyber-attacks that affected battery control systems in Korea, resulting in fire and damage.  These examples show that cyber-attacks can significantly affect the normal operation of electrical systems and have motivated much research around the world. Much of the published research deals with cyber-attack issues in electrical systems such as microgrids, smart grids and modern power systems. However, cyber-attacks in modular multilevel converters (MMCs) have received limited attention:  a recent letter (2021, see introduction section) is the only article published in this area so far. The MMC is deemed to be a prominent solution for medium to high-voltage and high-power applications, with several commercial converters adopting this approach and numerous projects worldwide using this topology. This project aims to investigate cyber-attack issues in the MMC control system and addresses the lack of investigation in this area. In particular, this research will consider the MMC in the context of high voltage direct current (HVDC) transmission systems since this topology is a promising solution to transfer power over long distances. It has been widely used in commercial projects (Trans Bay Cable, Dolwin2, Nano3-terminal DC grid, etc.). \r\n    In this project, distributed control schemes for controlling the MMC are considered. For this control approach, low-level control tasks are distributed among local controllers placed in the MMC submodules, while high-level control tasks are undertaken by a central controller. The computational burden for the central controller is therefore reduced. The distributed architecture is chosen since the MMC for HVDC applications requires a high number of submodules (SMs). In this case, if the traditional centralised control scheme is used, where a central controller is in charge of processing all the information required for implementing the whole control system, the execution time may not be sufficient for each control cycle to perform all the control tasks, limiting the modularity, flexibility and expandability of this topology (in terms of software development).\r\n     This project will investigate and quantify the impacts, in terms of operation and stability, of the type of cyber-attack named  \u0093false data injection attacks\u0094 (FDIAs ) on distributed control systems used for MMCs. Particular focus will be centred on designing strategies for detecting these cyber-attacks and locating the vulnerable sub-modules in the MMC. Also, novel cyber-attack-resilient distributed control schemes will be proposed. It must be pointed out that all the methods derived in this project will be validated through simulation and experimental results.\r\n      To this end, the cyber-attack detection methods will be based on state observers (Kalman filter, particle filter, etc.) and artificial intelligence (AI) based observers. Note that these detection methods should operate in a distributed architecture, meaning the state estimation should be performed based on partial information of the system. They should be able to be implemented on the SMs local controllers. Finally, once the cyber-attacks are identified, control schemes to neutralise those attacks will be investigated, generating cyber-attack-resilient distributed control schemes for the MMC.\r\n     The objectives of this proposal are (i) Analyse and quantify the effects of cyber-attacks on the standard distributed control strategies proposed for MMCs and the ones recently proposed based on the consensus theory, (ii) Design distributed methods for the detection of the cyber-attacks considered in this project, (iii) Design of cyber-attacks-resilient distributed control schemes for the MMC, and (iv) Implement an experimental rig for testing and validate the proposals derived from this research. Since there is no literature regarding cyber-attacks in MMCs, the literature review will be focused on work dealing with cyber-attacks on other electrical systems such as microgrids, smart grid and modern power systems. The aim will be to determine if the techniques proposed for these systems can be adapted for the MMC. A similar approach will be followed to address cyber-attack-resilient distributed control schemes. \r\nThe main contributions of this project will be:\r\n1.\tThe project will provide the foundation for research into cyber-attacks in MMC, as so far, there is very little information in the literature on this topic. Note that cyber-attacks are a hot topic in other electrical systems. Thus it should be investigated for the MMC.\r\n2.\tNovel distributed methods for detecting cyber-attacks in MMCs will be proposed and validated through simulations and experiment. \r\n3.\tNovel cyber-attack-resilient distributed control schemes for the MMC will be proposed and validated through simulations and experiment. \r\n4.\tAn experimental rig to analyse and validate the points mentioned above will be designed and built. It will be composed of a central controller and local controllers placed in each SM of the MMC.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11220586<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Marzo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26651\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Optimization and games with decision-dependent uncertainty: Theory, Algorithms and Applications\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26651\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26651\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Estudio de problemas de optimizaci\u00f3n y juegos con incertidumbre dependiente de decisiones. Estudio a nivel te\u00f3rico y  algor\u00edtmico. Estudio de aplicaciones.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11220807<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Julio 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27087\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Acceso a la vivienda en tiempos de crisis: estrategias de acceso al suelo de los pobres urbanos en Santiago de Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27087\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27087\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La investigaci\u00f3n analizar\u00e1 las estrategias desplegadas por hogares de bajos ingresos en etapa de formaci\u00f3n, en la resoluci\u00f3n del trade-off acceso a vivienda formal mal localizada o acceso a ciudad usando estrategias informales de acceso a vivienda. El aumento del precio del suelo y la consecuente falta de suelo para la construcci\u00f3n de vivienda de inter\u00e9s social, junto con la mala localizaci\u00f3n de ella, ser\u00edan antecedentes relevantes para la configuraci\u00f3n de una serie de estrategias de los hogares vulnerables, para lidiar con el trade-off entre acceso a vivienda o acceso a la ciudad.\r\n\r\nLa crisis de acceso a la vivienda formal queda reflejada en hechos como: el aumento de campamentos y de familias que habitan en ellos, llegando a un m\u00e1ximo hist\u00f3rico entre el 2020-2021 (CES, 2021); el d\u00e9ficit cuantitativo de vivienda que supera por creces la capacidad de construcci\u00f3n de vivienda social en el periodo actual (Gascic, 2021); los niveles de hacinamiento que ha puesto en evidencia la pandemia; el incremento en los precios de arriendo y de compra de vivienda, las altas tasas de allegamiento, entre otros.\r\n\r\nSi bien tradicionalmente se ha desarrollado investigaci\u00f3n que apunta a la cr\u00edtica del funcionamiento del mercado del suelo y la pol\u00edtica de vivienda, que se ha subordinado al mercado, se ha prestado poca atenci\u00f3n a los siguientes fen\u00f3menos: a) La capacidad de agencia de los hogares en la toma de decisiones residenciales y c\u00f3mo ellos son capaces de resolver, a trav\u00e9s del uso de estrategias formales e informales, o una combinaci\u00f3n de ambas, el acceso a vivienda\/localizaci\u00f3n en la ciudad; b) La racionalidad, motivaciones o drivers de la elecci\u00f3n de esa localizaci\u00f3n.\r\nEs por ello, que la investigaci\u00f3n se pregunta: \u00bfCu\u00e1les son las racionalidades usadas en las estrategias de los hogares pobres para acceder a una localizaci\u00f3n en la ciudad que supere el trade-off de vivienda versus localizaci\u00f3n?\r\nLa principal hip\u00f3tesis de investigaci\u00f3n es que en el actual contexto de aumento generalizado de precios del suelo y a pesar de la disminuci\u00f3n del d\u00e9ficit habitacional seg\u00fan las cifras oficiales, crece la proporci\u00f3n de nuevos hogares de bajos ingresos que acceden a vivienda por v\u00edas informales motivados por permanecer en la ciudad o mejorar su localizaci\u00f3n en ella. Estas estrategias tienen en com\u00fan saltarse la institucionalidad urbana porque implican una ocupaci\u00f3n ilegal del suelo -no ajustada al derecho a propiedad- y\/o porque implican una falta de sujeci\u00f3n a las normas urbanas.  \r\nEl foco de la investigaci\u00f3n est\u00e1 en Santiago, ya que se presume que es en esta zona donde se encontrara una diversidad relevante de estrategias de acceso a vivienda. Se considerar\u00e1n hogares en formaci\u00f3n, es decir, cuyos jefes de hogar est\u00e9n entre 18 y 40 a\u00f1os, en etapa de decisi\u00f3n de localizaci\u00f3n.\r\nPara llevar a cabo la investigaci\u00f3n, se realizar\u00e1n tres fases de recolecci\u00f3n de informaci\u00f3n: un an\u00e1lisis de distintas bases de datos que busca identificar las estrategias y su localizaci\u00f3n en la ciudad. En una segunda etapa, la investigaci\u00f3n busca caracterizar esas estrategias a partir de la racionalidad de la elecci\u00f3n y los drivers que se movilizan y en tercer lugar, se cuantificar\u00e1 la presencia de estrategias y los factores que moldean la decisi\u00f3n en los distintos casos.\r\nDentro de las principales actividades contempladas se realizar\u00e1 una estancia en Francia para compartir con el equipo del PRODIG (P\u00f4le de recherche pour l\u0092organisation et la diffusion de l\u0092information g\u00e9ographique) centro de investigaci\u00f3n en Geograf\u00eda con el cu\u00e1l la investigadora ha incursionado en redes de investigaci\u00f3n para trabajar temas de desigualdades urbanas, sobre todo en las \u00e1reas perif\u00e9ricas de las ciudades. El PRODIG centra su investigaci\u00f3n en Am\u00e9rica Latina, lo que permitir\u00e1 contrastar los resultados con otras realidades; la participaci\u00f3n en los congresos ISA, RC-21 y LASA para formar redes de investigaci\u00f3n; la formaci\u00f3n de 4 tesistas de magister. Dentro de los productos, se desarrollar\u00e1n dos art\u00edculos de divulgaci\u00f3n cient\u00edfica, un seminario de cierre, un mapa de localizaci\u00f3n de estrategias y un set de indicadores para identificarlas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Marzo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26599\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Decision-focused learning under the lens of mathematical programming\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26599\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26599\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Numerous real-life decision-making processes involve solving a task with uncertain input that can be estimated from historic data. There is a growing interest in decision-focused learning methods (a.k.a. smart predict-then-optimize) whose goal is to find models that fit the data while considering how the predicted input will perform in a particular task. For example, the task can be a shortest path problem that uses predictions on travel times in the objective function. Fitting the data and ignoring the task may lead to sub-optimal decisions. Sometimes, uncertainty is involved in the constraints of the model. In this case, ignoring the task would lead to infeasible decisions. The goal of this project is to develop efficient exact algorithms and new applications to train a Machine Learning models that perform well in one or several tasks using mathematical programming (MP) tools.\r\n\r\nIn this context, the typical measure of a predictor is the regret: the excess cost incurred when making a suboptimal decision due to an imprecise predictor. This problem is bilevel in nature: the top-level decision consists in determining a predictor that minimizes a regret while considering that the predictions will affect a task, e.g. an optimization problem in a lower level. This structure is typically non-convex and non-continuous, making the problem difficult to solve for realistic instances. However, several recent advances in bilevel-tailored approaches exploit this structure and can solve large scale problems.\r\n\r\nThere are two main ways of estimating task-oriented predictors: 1) stochastic gradient-based methods; and 2) MP reformulations of the problem. Stochastic gradient-based methods replace the non-differentiable regret for some differentiable surrogate loss function approximating the real loss. Due to advances in neural network implementations and stochastic gradient-descent this approach is the most applied among researchers and practitioners in the Machine Learning community.\r\n\r\nMP for data science has attracted the attention of researchers and practitioners in different areas as mathematics, operations research, computer science during the last years. It provides some degree of flexibility, being able to model desirable considerations for predictions models. For instance, MP has been successfully used to train sparse models yielding improved explainability and\/or fairness. Moreover, MP models are in many cases solvable by any off-the-shelf solver. However, for the decision-focused learning problem there are still many gaps using MP formulations. To the best of our knowledge, MP formulations have been used only for surrogate loss functions.\r\n\r\nBehind the low usage of MP tools is the scalability. A typical ML setting involves data sets involving thousands of observations. In consequence, the training task becomes more difficult. To tackle this issue, decomposition methods such as cut and column generation can help to solve problems at scale. We aim to provide efficient exact methods that can return either optimal solutions, or optimality guarantees for large scale instances.\r\n\r\nDuring the last years, decision-focused learning has been widely applied to combinatorial optimization problems. However, this approach can also be used in many other applications such as Markov decision processes (MDPs) or game theory. In the first case, we can take algorithmic advantage of well-known existing algorithms for MDPs such as value iteration or policy iteration, or approximation techniques such as Q-learning. The game-theoretic setting is more challenging: depending on the notion of equilibrium the loss function would change. For instance, the definition of regret can be applied straightforwardly to Stackelberg equilibria (or leader-follower equilibria), a concept widely applied to energy markets, security and transportation. In the case of Nash equilibrium, the definition of regret is not direct anymore. We hope to develop models that adapt the decision-focused learning paradigm to this broader context.\r\n\r\nThe study of this topic requires the use and development of MP of tools along with their algorithmic analysis. During the project, we expect to develop efficient of algorithms that can be used by decision making, as well as contribute in the understanding of the theoretical aspects of decision-focused learning.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11220843<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26969\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Noticing en un curso de Desarrollo Profesional: Atendiendo al pensamiento algebraico de estudiantes de educaci\u00f3n b\u00e1sica\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26969\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26969\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Esta investigaci\u00f3n se centra en el conocimiento del profesor de matem\u00e1ticas de educaci\u00f3n b\u00e1sica en ejercicio y se sit\u00faa como la continuaci\u00f3n de un proyecto de investigaci\u00f3n adjudicado en 2020 por el IR (La construcci\u00f3n del pensamiento algebraico en la Formaci\u00f3n Inicial Docente: un estudio exploratorio). El inter\u00e9s de este proyecto de iniciaci\u00f3n en investigaci\u00f3n 2022 est\u00e1 puesto en indagar c\u00f3mo los docentes consideran el pensamiento matem\u00e1tico de sus estudiantes para interpretar situaciones de ense\u00f1anza-aprendizaje y tomar decisiones en el momento. Dado que los contextos de ense\u00f1anza de las matem\u00e1ticas son complejos y din\u00e1micos, los programas o cursos de Desarrollo Profesional son considerados un espacio para comprender y enriquecer el conocimiento profesional de los docentes, los cuales deben estar al servicio del aprendizaje y rendimiento de los estudiantes. Como una forma de abordar el conocimiento profesional de los docentes se encuentra la competencia del Noticing, la cual permite resolver tareas profesionales y se considera un elemento crucial de la experticia del profesor de Matem\u00e1ticas. Sin embargo, la especificidad en el conocimiento del profesor hace necesario profundizar en el desarrollo del Noticing a trav\u00e9s de diferentes dominios de conocimiento de las matem\u00e1ticas escolares. De esta forma, esta investigaci\u00f3n indagar\u00e1 en describir c\u00f3mo profesores de matem\u00e1ticas de educaci\u00f3n b\u00e1sica en ejercicio promueven el pensamiento algebraico de sus estudiantes. As\u00ed, el tema de este proyecto extiende la investigaci\u00f3n previa que se ha centrado, principalmente, en la formaci\u00f3n inicial docente y en alguno de los aspectos del \u00e1lgebra (como los patrones). Los objetivos generales de investigaci\u00f3n son:\r\n\u0095\tCaracterizar el conocimiento profesional evidenciado por docentes de educaci\u00f3n b\u00e1sica sobre el fomento del pensamiento algebraico al participar de un curso de DP.\r\n\u0095\tIdentificar las acciones desarrolladas en un curso de DP que fomentan la competencia del Noticing en los docentes de educaci\u00f3n b\u00e1sica.\r\nConceptualmente, la competencia del Noticing se aborda desde el componente \u0093Atender al pensamiento matem\u00e1tico de los estudiantes\u0094 (Jacobs, Lamb y Philipp, 2010) y su prop\u00f3sito central es comprender las caracter\u00edsticas del pensamiento de los estudiantes, interpretarlo y tomar decisiones informadas. Este componente involucra tres habilidades interrelacionadas: (a) prestar atenci\u00f3n a las estrategias de los estudiantes; (b) interpretar sus comprensiones; y (c) decidir c\u00f3mo responder sobre la base de dichas comprensiones. Adicionalmente, este proyecto se basa en el marco conceptual del \u00e1lgebra propuesto por Kaput (2008), el cual organiza la ense\u00f1anza del \u00e1lgebra a trav\u00e9s de cuatro pr\u00e1cticas (generalizaci\u00f3n, representaci\u00f3n, justificaci\u00f3n y razonamiento) que se encuentran presente en cada uno de los enfoques al pensamiento algebraico (aritm\u00e9tica generalizada; equivalencia, expresiones, ecuaciones e inecuaciones; y pensamiento funcional).\r\nDe manera general, este proyecto sigue las directrices metodol\u00f3gicas de la Investigaci\u00f3n de Dise\u00f1o (Swan, 2020). Participar\u00e1n 20 profesores de educaci\u00f3n b\u00e1sica que realizan clases de matem\u00e1ticas en colegios municipales con los cuales la Instituci\u00f3n Patrocinante tiene convenios. Para indagar c\u00f3mo se desarrolla la habilidad del Noticing en el curso de Desarrollo Profesional sobre pensamiento algebraico, los docentes participar\u00e1n del curso, as\u00ed como de entrevistas individuales semiestructuradas y de grabaciones de clases. El foco de an\u00e1lisis de la informaci\u00f3n estar\u00e1 centrado en las producciones orales y escritas de los docentes, los cuales permitir\u00e1n analizar c\u00f3mo se va desarrollada la competencia descrita.\r\nEste proyecto contempla la ejecuci\u00f3n de cuatro etapas a desarrollar en dos a\u00f1os: (a) dise\u00f1o inicial del curso de Desarrollo Profesional; (b) recogida de la informaci\u00f3n; (c) organizaci\u00f3n y an\u00e1lisis de datos; y (d) difusi\u00f3n de resultados.\r\nEl impacto esperado de los resultados influir\u00e1 en tres \u00e1reas principales: (a) investigaci\u00f3n e internacionalizaci\u00f3n, consolidando y posicionando una l\u00ednea de investigaci\u00f3n novedosa en el campo de la educaci\u00f3n matem\u00e1tica; (b) docencia en pre y posgrado, enriqueciendo la formaci\u00f3n inicial y contin\u00faa de profesores; y (c) redes de colaboraci\u00f3n, lo cual permitir\u00e1 seguir estableciendo un trabajo conjunto con investigadores nacionales e internacionales interesados en la mejora de las pr\u00e1cticas matem\u00e1ticas que se realizan en el aula.\r\n\r\nReferencias\r\nJacobs, V. R., Lamb, L. L. y Philipp, R. A. (2010). Professional noticing of children\u0092s mathematical thinking. Journal for Research in Mathematics Education, 2(41), 169-202.\r\nKaput, J. (2008). What is algebra? What is the algebraic reasoning? En J. . Kaput, D. W. Carraher y M. L. Blanton (Eds.), Algebra in the early grades (pp. 5-17). Nueva York, NY: Lawrence Erlbaum Associates.\r\nSwan, M. (2020). Design Research in Mathematics Education. En S. Lerman (Ed.), Encyclopedia of Mathematics Education (pp. 192-195). Springer. https:\/\/doi.org\/10.1007\/978-3-030-15789-0_180.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1221032<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Marzo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27092\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Medici\u00f3n del efecto del habla sincronizada en la inteligibilidad y la comprensibilidad en aprendientes de ingl\u00e9s como lengua extranjera\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27092\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27092\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"].[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1220209<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Marzo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27093\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            On the effects of implicit and explicit corrective feedback on perception and production of English sentence accent and (post)nuclear intonation as moderated by L2 foreign language aptitude, working memory and musical ability\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27093\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27093\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"].[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1220762<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Diciembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27101\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27101\" aria-expanded=\"false\" aria-controls=\"collapse-27101\">\n                                            Adaptive Mobilities: daily mobility in the Chilo\u00e9 Archipi\u00e9lago\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27101\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27101\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Movilidades Adaptativas \u0093Adaptive mobilities a transdisciplinary approach to daily mobility on the chilo\u00e9 archipelago\u0094 es un proyecto Fondecyt Regular 1220762 (2022-2025) cuyo objetivo general es analizar la movilidad cotidiana en 4 sistemas archipel\u00e1gicos (Calbuco, Chauques, Quinchao y Desertores), enfatizando tanto en las experiencias adaptativas y sus interrelaciones con actores humanos y no-humanos, como en la animaci\u00f3n de formas de encuentro dial\u00f3gico entre investigadores e isle\u00f1os.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1220508<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Diciembre 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27103\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27103\" aria-expanded=\"false\" aria-controls=\"collapse-27103\">\n                                            Violencia de G\u00e9nero en el \u00e1mbito de la (ex)pareja: Interseccionalidad, agencias y resistencias\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27103\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27103\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El presente estudio se centra en la violencia de g\u00e9nero en relaciones de pareja a partir de experiencias de j\u00f3venes universitarias chilenas, examinando el maltrato psicol\u00f3gico, f\u00edsico y sexual.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Febrero 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25971\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            The epidemiology of antimicrobial resistance in a region with intense aquaculture activity: evaluating the role of bivalve mollusks as sentinel organisms and potential impacts on public health\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25971\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25971\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Antimicrobial resistance (AMR) is a phenomenon that happens when bacteria become tolerant to antibiotics used to treat the infections they cause. Antibiotics are key therapeutic tools to treat many human and animal infectious diseases; consequently, keeping their activity on bacteria is fundamental for public and animal health. Aquaculture farming is known for using large amounts of antibiotics, making this activity particularly relevant in development and spread of AMR in aquatic environments. There is evidence in Chile that aquaculture activity increases the presence of resistant bacteria and their corresponding genes in marine sediments directly impacted by salmon farms; however, these evaluations are limited to few locations which hampers a generalization of these conclusions to other salmon farming sites in Chilean waters. There is also evidence suggesting that aquaculture-associated resistance genes present in marine sediments might be transferred to bacteria with pathogenic potential in humans such as Escherichia coli, but no studies have reported the presence of resistance traits in such bacteria in the marine environment from areas impacted by salmon farming in Chile. In countries like Norway, bivalve mollusks are used to monitor antibiotic resistance in Enterobacteria in the marine environment; therefore, they could also be useful for monitoring AMR associated with salmon farming and other anthropogenic sources in Chile. Sampling of bivalve mollusks represents an important logistical advantage to complex and expensive seabed sediment sampling. Los Lagos is the region with the highest historical production of farmed salmon in Chile; then, it is a suitable area to investigate the impact of aquaculture-sourced AMR in the marine environment.\r\nThe general objective of this proposal is to investigate aquaculture-associated AMR in the marine environment of Los Lagos region from an epidemiologic approach, using bivalve mollusks as sentinel organisms and E. coli as the indicator bacterium. Specific objectives include: 1) to detect, characterize and estimate the prevalence of AMR in E. coli isolated from bivalve mollusks in the Los Lagos region, through a region-level sampling; 2) to study the spatial variability of AMR in E. coli isolated from bivalve mollusks from Los Lagos region; 3) to evaluate the effect of salmon farming activity on the richness and intensity of AMR in E. coli isolated from bivalves from Los Lagos region, controlling for potential confounding factors; and 4) to determine whether significant differences exist in the accumulation of E. coli and resistant E. coli in bivalve mollusks between the sampled bivalve species, accounting for environmental and biological factors.\r\nBivalve mollusks samples will be obtained the 130 sampling stations set along the coast of Los Lagos by the National Program for Surveillance and Control of Harmful Algal Blooms Intoxications (red tides) coordinated by the Ministry of Health. Thirty-three additional sampling stations will be set in the same study area in order to achieve the calculated total sample size of 163 sampling stations. At each sampling station bivalve mollusks will be sampled to quantify E. coli and to detect and characterize both phenotypic and genotypic AMR in this bacterium. The study will be focused in 29 antimicrobial resistance genes (ARGs) and 20 antibiotics commonly used in salmon farming or for which resistance has been detected in previous studies. The antimicrobial susceptibility will be performed by estimating the minimal inhibitory concentrations (MICs) for each antibiotic using the VITEK2 technology. The genotypic analysis will be carried out by means of the detection target ARGs, through PCR. Spatial clustering will be examined for each antibiotic tested using MIC values and the ARG richness index; global clustering will be evaluated through the Moran\u0092s I statistic, while local clustering will be examined by means of the spatial scan statistic. ARG richness will be modeled as a function of the local salmon farming intensity expressed as the number of active salmon farms within 10 km seaway distance from the bivalve sampling location, using a Poisson mixed-effects model in order to control for other AMR sources and important environmental variables. Similar models will be constructed using MICs as the outcome for antimicrobials that show substantial variability in this parameter. Finally, the abundance of both total and resistant E. coli (MPN\/100g) found in bivalve mollusks will be modeled as a function of the bivalve species sampled, accounting for bivalve size, water temperature, local salmon farming intensity and distance to other AMR sources, using a mixed-effect linear regression model.\r\nThis study will contribute to characterize and to identify the main drivers of the environmental AMR in an area with intense salmon farming activity, and it will help to understand how this AMR can impact public health through potential pathogenic bacteria. In practice, this proposal will be the first extensive epidemiological study in this matter in Chile. Moreover, this proposal will help to determine which bivalve mollusks species are suitable to monitor AMR in environments impacted by salmon farming. All this information will be crucial to set the foundations for a future AMR monitoring program in areas of intense aquaculture.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Enero 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26071\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Pr\u00e1cticas art\u00edsticas de mediaci\u00f3n con comunidades: desaf\u00edos para expandir el rol social de las artes en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26071\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26071\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto tiene como prop\u00f3sito comprender c\u00f3mo las pr\u00e1cticas art\u00edsticas de mediaci\u00f3n son un aporte para abordar problem\u00e1ticas socioculturales y generar estrategias para implementar dichas pr\u00e1cticas en diversos contextos y comunidades del pa\u00eds, expandiendo el rol social de las artes. \r\nSu ejecuci\u00f3n esta contemplada en cuatro regiones del pa\u00eds y en Barcelona, Espa\u00f1a, a trav\u00e9s de diferentes casos de estudio y un acucioso trabajo de campo.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1220066<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Febrero 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26082\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26082\" aria-expanded=\"false\" aria-controls=\"collapse-26082\">\n                                            Pr\u00e1cticas art\u00edsticas de mediaci\u00f3n con comunidades: desaf\u00edos para expandir el rol social de las artes en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26082\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26082\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto \u0093Pr\u00e1cticas Art\u00edsticas de Mediaci\u00f3n con Comunidades: Desaf\u00edos para Expandir el Rol Social de las Artes en Chile\u0094, desarrollado bajo el programa Fondecyt Regular n\u00b0 1220066, tuvo como objetivo general comprender c\u00f3mo las pr\u00e1cticas art\u00edsticas de mediaci\u00f3n contribuyen a abordar problem\u00e1ticas socioculturales, generando estrategias que expandan el rol social de las artes en diversos contextos y comunidades del pa\u00eds&#8203;.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Febrero 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26086\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Aprendizaje activo para algoritmos basados en bolsas de caracter\u00edsticas con aplicaciones en textos e im\u00e1genes\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26086\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26086\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26087\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Nuevos m\u00e9todos computacionales para caracterizar la arquitectura gen\u00e9tica de reordenamientos gen\u00f3micos complejos en c\u00e1nceres Chilenos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26087\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26087\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El c\u00e1ncer es la segunda causa de muerte en la poblaci\u00f3n Chilena y se proyecta que en diez a\u00f1os ser\u00e1 la primera causa de muerte en el pa\u00eds. A nivel regional, la regi\u00f3n de O Higgins es la que presenta la mayor incidencia de muertes por c\u00e1ncer. Actualmente, Chile invierte alrededor del 1% del PIB en atenci\u00f3n y tratamiento del c\u00e1ncer. Es indispensable y urgente comenzar a caracterizar molecularmente los c\u00e1nceres prevalentes de la poblaci\u00f3n Chilena pues esto permitir\u00e1 integrar informaci\u00f3n que impactar\u00e1 las decisiones cl\u00ednicas permitiendo la implementaci\u00f3n de tratamientos espec\u00edficos para los pacientes. El estudio gen\u00f3mico y molecular de sistemas biol\u00f3gicos complejos, como el desarrollo y progresi\u00f3n del c\u00e1ncer, requieren del desarrollo de nuevos algoritmos y modelos te\u00f3ricos para analizar e interpretar datos gen\u00f3micos complejos (big- data). El principal objetivo del laboratorio de gen\u00f3mica computacional que instalar\u00e9 en el instituto de ciencias de la ingenier\u00eda de la Universidad de O Higgins ser\u00e1 desarrollar investigaci\u00f3n de vanguardia entorno al dise\u00f1o y aplicaci\u00f3n de nuevos algoritmos y tecnolog\u00edas \u00f3micas para estudiar la arquitectura gen\u00f3mica de c\u00e1nceres prevalentes de la poblaci\u00f3n Chilena. La meta a largo plazo es trasladar estas tecnolog\u00edas a la pr\u00e1ctica cl\u00ednica e impulsar la implementaci\u00f3n de programas de medicina de precisi\u00f3n enfocados en el tratamiento y prevenci\u00f3n del c\u00e1ncer en nuestro pa\u00eds y regi\u00f3n. Un segundo objetivo es impulsar y liderar investigaci\u00f3n multidisciplinaria en tem\u00e1ticas de salud, agroindustria y miner\u00eda, sectores cr\u00edticos a desarrollar en la regi\u00f3n de O'Higgins. Finalmente, el laboratorio de gen\u00f3mica computacional contribuir\u00e1 a la formaci\u00f3n de capital humano avanzado en \u00e1reas asociadas a la gen\u00f3mica, bioinform\u00e1tica y biolog\u00eda computacional.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Febrero 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26129\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Sensing a Disturbance in the Flow: Crosstalk Between Shear Stress and Hypoxia in the Early Origins of Vascular Dysfunction\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26129\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26129\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]During the last decades, compelling evidence shows how the context in which early life takes place impinges risk or protection for later development of non-communicable chronic diseases. In this regard, impaired fetal growth, as occur in the fetal growth restriction (FGR), leads to a higher risk for later cardiovascular diseases, an effect that would be mediated by accelerated aging at molecular, structural, and functional levels. FGR remains a leading cause of perinatal morbidity and mortality, affecting ~10% of pregnancies, but ranging 5 to 25% depending on the nutritional and health conditions of the population surveyed, with a higher prevalence among pregnant women of low socioeconomic status. In the clinic, FGR is normally defined by a fetal weight below the 10th percentile, however, new evidence shows that impaired intrauterine growth may affect several neonates born over the 10th percentile, which may be missed from the perinatal survey for preventing adverse outcomes. This points out the need for further studies to improve the understanding and identification of altered fetal growth trajectories and their consequences on vascular function. Studies in placenta show that FGR vascular dysfunction is also found at birth in chorionic and umbilical arteries. We have demonstrated the presence of functional and molecular markers (e.g. epigenetic changes) of endothelial dysfunction in human umbilical and chorionic vessels, findings that have been further confirmed by comparing systemic (aorta and femoral arteries) and umbilical arteries in animal models of FGR. These traits suggest that umbilical artery endothelial cells (HUAEC) can be used as a surrogate to explore the vascular programming within the fetus, however, their translation to clinical preventive applications for promoting healthy aging deserves further studies. It worth noting that fetal reduced oxygen supply (i.e. fetal hypoxia) and altered blood flow patterns (i.e. shear stress) are key clinical markers in the FGR, independently of the constraints leading to impaired growth, and both factors exert a tight control of vascular development and function across life. However, how these key stimuli interact and impose an epigenetic program on the endothelial function remains elusive. This proposal will focus on the crosstalk between hypoxia and shear stress that results in the endothelial programming related to impaired fetal growth, and the molecular mechanisms that mediate the vascular responses to these stimuli. Furthermore, we will address if these molecular markers may allow detecting early vascular aging in FGR subjects beyond the 10th centile cutoff. We hypothesize that \u0093Impaired fetal growth conditions are associated with epigenetic programming of aging- and mechanosensing-related miRNAs and transcripts in the endothelium, which can be triggered by the confluence of altered flow patterns and hypoxia resulting in molecular and structural pro-hypertensive biomechanical vascular properties\u0094. This hypothesis will be addressed by three General Objectives (GO) involving ex vivo, in vitro, and in vivo observational and mechanistic approaches: GO1 To demonstrate, in HUAEC, whether late FGR results in epigenetic changes related to the regulation of vascular aging and the expression of mechanosensing mechanisms involved in the endothelial-dependent relaxation, and their relationship with general prenatal parameters of vascular health. GO1 will be performed by recruiting HUAEC samples from late FGR and control pregnancies, to assess transcriptomic and DNA methylation analyses that will be crossed with prenatal clinical data. GO2 To study, in vivo, whether stimuli related to FGR (i.e. hypoxia and altered shear stress) differentially regulate mechanosensing pathways involved in the endothelial-dependent relaxation and their relationship with the in vivo and ex vivo vascular properties (e.g. functional and biomechanical). GO2 will be performed in chicken embryos exposed to hypoxia and treated with agents targeting mechanosensing pathways, in which wall shear stress will be determined by Ultrasound Localization Microscopy, with complementary functional, structural, and molecular analyses. GO 3. To study, in cultured HUAEC, whether stimuli related to impaired fetal growth converge in the regulation of mechanosensing-and aging-related transcripts and miRNA, contributing to the cellular programming of endothelial dysfunction. OG3 will be performed in HUAEC exposed, in vitro, to sustained hypoxia and diverse flow patterns (shear stress), in which target DNA methylation, miRNA, transcripts, and proteins will be assessed. Our expected outcome is to improve the knowledge about the endothelial epigenetic programming after FGR and enhance the characterization of in vivo shear stress patterns and mechanisms induced by chronic fetal hypoxia. This project is not only relevant to uncover the developmental approaches for diagnosing and treatments in complicated pregnancies.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Diciembre 2029<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26243\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Centro de Modelamiento Matem\u00e1tico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26243\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26243\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El Centro de Modelamiento Matem\u00e1tico (CMM) es un centro cient\u00edfico l\u00edder en Chile para la investigaci\u00f3n y aplicaciones de las matem\u00e1ticas. Fue inaugurado en abril del 2000 y forma parte de la Facultad de Ciencias F\u00edsicas y Matem\u00e1ticas (FCFM) de la Universidad de Chile, en la que se encuentra la principal y m\u00e1s antigua escuela de ingenier\u00eda del pa\u00eds. Su objetivo es crear nuevas matem\u00e1ticas y utilizarlas para resolver problemas provenientes de otras ciencias, la industria y las pol\u00edticas p\u00fablicas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ACT210046<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Marzo 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26319\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Compound and Cascading Climate Extremes in Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26319\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26319\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Chile se ha visto cada vez m\u00e1s afectado por m\u00faltiples eventos extremos clim\u00e1ticos que ocurren simult\u00e1neamente,\r\ncomo eventos compuestos, o consecutivamente, como eventos en cascada.\r\nLos eventos clim\u00e1ticos se consideran compuestos cuando ocurren al mismo tiempo. Por ejemplo, el centro de\r\nChile (la regi\u00f3n m\u00e1s poblada del pa\u00eds) se ha visto afectada por sequ\u00edas frecuentes y severas, agravadas por el\r\naumento de las olas de calor (HWs) que a su vez han favorecido persistentes incendios forestales. Estos eventos\r\nextremos han afectado la econom\u00eda al da\u00f1ar cultivos y provocar escasez de alimentos para el ganado.\r\nLos eventos en cascada act\u00faan como una serie de fichas de domin\u00f3 que se derrumban. Por ejemplo, en el sur de\r\nChile, las fuertes lluvias orogr\u00e1ficas asociadas con potentes r\u00edos atmosf\u00e9ricos (ARs) han provocado graves\r\ninundaciones que, al arrastrar sedimentos ricos en nutrientes a lagos y fiordos, a menudo han favorecido\r\nfloraciones de algas nocivas (HABs). En la misma regi\u00f3n, el r\u00e1pido derretimiento de los campos de hielo\r\npatag\u00f3nicos no solo est\u00e1 canalizando hierro hacia lagos y fiordos (favoreciendo m\u00e1s floraciones de algas), sino\r\nque tambi\u00e9n ha formado cientos de nuevos lagos. El vaciamiento repentino de lagos glaciales (GLOFs) han\r\nprovocado deslizamientos de tierra e inundaciones que han borrado del mapa peque\u00f1os poblados en la\r\nPatagonia.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad Adolfo Ib\u00e1\u00f1ez<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26431\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estilos alimentarios vinculados a la sobreingesta de padres y\/o cuidadores primarios y su relaci\u00f3n con los comportamientos alimentarios de los ni\u00f1os\/as.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26431\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26431\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto de investigaci\u00f3n busca caracterizar la relaci\u00f3n entre los estilos alimentarios vinculados a la sobreingesta de adultos y los comportamientos alimentarios de preescolares a cargo de estos adultos.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Enero 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad Adolfo Ib\u00e1\u00f1ez<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26433\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Intervenir sin estigmatizar: Red de Formaci\u00f3n para la erradicaci\u00f3n del Estigma de Peso en Poblaci\u00f3n Infanto-Juvenil.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26433\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26433\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Descripci\u00f3n del problema a tratar: En Chile, actualmente la obesidad se ha transformado en un problema de salud p\u00fablica, que ha ido en\r\ncreciente aumento, ubic\u00e1ndonos en los primeros lugares a nivel mundial. En poblaci\u00f3n infantil, se ha detectado que la prevalencia se ha\r\ncuadruplicado entre los a\u00f1os 80 y 90, y actualmente se se\u00f1alan cifras mayores al 30%, especialmente al indagar en niveles socioecon\u00f3micos\r\nm\u00e1s bajos (INTA, 2021). En vista de que la obesidad constituye una condici\u00f3n de salud cr\u00f3nica, altamente prevalente, compleja, progresiva\r\ny recidivante, la adherencia terap\u00e9utica se torna un factor esencial a preservar y potenciar a la hora de planificar y ejecutar intervenciones\r\nde cara a frenar la ganancia de peso poblacional. Pese a lo anterior, en el abordaje de la obesidad, tanto a nivel preventivo, como en el\r\n\u00e1mbito de la intervenci\u00f3n, se observa una preocupante paradoja, ya que, pese a que las atenciones sanitarias puedan estar disponibles, a\r\nmenudo a las personas se les dificulta el acceso a estas, debido a pr\u00e1cticas discriminatorias existentes en los entornos sanitarios. El estigma\r\ny la discriminaci\u00f3n en salud tiene distintas formas, desde la negaci\u00f3n de atenciones m\u00e9dicas y las barreras injustas para la prestaci\u00f3n de\r\nservicios, las atenciones de peor calidad, hasta la aplicaci\u00f3n de procedimientos obligatorios, como por ejemplo el pesaje en contextos no\r\nadecuados. Lo anterior puede verse influido por los sesgos, estigma y discriminaci\u00f3n en funci\u00f3n del peso que, muchas veces, presentan y\r\nejercen los profesionales de salud encargados de atender a las personas que viven en cuerpos grandes. La investigaci\u00f3n ha documentado\r\nampliamente la presencia de estigma de peso en los entornos sanitarios, creando dificultades adicionales y barreras para el acceso a\r\natenciones de calidad en las\/os usuarias\/os de mayor peso corporal.\r\nSoluci\u00f3n propuesta: En vista de todo lo anteriormente planteado, y de cara a poder fortalecer el desarrollo de futuras intervenciones para\r\nafrontar el exceso de peso en poblaci\u00f3n infanto-juvenil, y postulaciones a fondos concursables a partir de los cuales financiar estos\r\nprogramas, es que se plantea, como primer paso, el crear una red de colaboraci\u00f3n internacional que permita acceder a formarnos y a\r\nformar a nuestros estudiantes en una aproximaci\u00f3n no estigmatizante hacia la vivencia de personas que habitan en cuerpos grandes. Esta\r\nsoluci\u00f3n se plantea tomando en cuenta las recomendaciones que emergen de distintos estudios, en los que se remarca la necesidad de\r\ndedicar m\u00e1s recursos desde la pol\u00edtica p\u00fablica e investigaci\u00f3n para involucrar y apoyar a personas de mayor peso, adem\u00e1s de la necesidad\r\nde realizar capacitaci\u00f3n obligatoria del personal sanitario en estas tem\u00e1ticas, enfoc\u00e1ndose en la concienciaci\u00f3n del estigma, dado el\r\nimpacto de este fen\u00f3meno en los indicadores de atenci\u00f3n m\u00e9dica y salud de las\/os usuarias\/os. Espec\u00edficamente, se propone contribuir a la\r\nsoluci\u00f3n de esta problem\u00e1tica mediante dos focos de acci\u00f3n: (a) Realizaci\u00f3n de una investigaci\u00f3n que permita establecer la presencia de\r\nsesgos, estigma y conductas discriminatorias en funci\u00f3n del peso corporal en profesionales de la salud que realizan atenci\u00f3n directa de\r\npoblaci\u00f3n infanto-juvenil. Lo anterior permitir\u00eda establecer un diagn\u00f3stico a partir de la cual priorizar los focos a abordar, de cara a\r\nactividades formativas o intervenciones en este \u00e1mbito. Para la planificaci\u00f3n y ejecuci\u00f3n de esta investigaci\u00f3n, el trabajo conjunto de la red\r\npropuesta resulta esencial, representando este el primer hito colaborativo de la misma. (b) Realizaci\u00f3n de distintas actividades de\r\ndivulgaci\u00f3n, tanto abocadas a nuestra comunidad educativa, como dirigidas a la poblaci\u00f3n objetivo, es decir, profesionales de la salud que\r\nrealizan atenci\u00f3n directa de poblaci\u00f3n infanto-juvenil. Para este hito se requerir\u00e1 el traslado del Dr. S\u00e1nchez-Carracedo y de la Dra. Oda a la\r\nciudad de Santiago, para poder realizar estas actividades en las dependencias de nuestra casa de estudios.\r\nMetodolog\u00eda: El presente proyecto plantea construir una red de colaboraci\u00f3n internacional mediante tres aristas principales: (a) A nivel\r\ninternacional, se plantea establecer una relaci\u00f3n colaborativa con uno de los expertos iberoamericanos en el abordaje de esta problem\u00e1tica\r\nen poblaci\u00f3n infanto-juvenil, el Dr. David S\u00e1nchez-Carracedo, quien es profesor titular del Departamento de Psicolog\u00eda Cl\u00ednica y de la Salud\r\nde la Universidad Aut\u00f3noma de Barcelona. El acad\u00e9mico colaborar\u00eda en actividades de formaci\u00f3n y sensibilizaci\u00f3n en el tema para nuestra\r\ncomunidad educativa, adem\u00e1s de asesorar te\u00f3rica y metodol\u00f3gicamente en la planificaci\u00f3n de la investigaci\u00f3n propuesta en el apartado\r\nanterior. (b) La segunda arista de esta red consistir\u00eda en formalizar la colaboraci\u00f3n con la Dra. Camila Oda, acad\u00e9mica del Instituto de\r\nCiencias Sociales de la Universidad de O\u0092Higgins, qui\u00e9n adem\u00e1s de ser una colaboradora hist\u00f3rica del Centro de Estudios de la Conducta\r\nAlimentaria (CECA), lleva varios a\u00f1os dedicada al estudio de las variables relacionadas con los trastornos vinculados con la alimentaci\u00f3n y el\r\npeso y la obesidad, especialmente abocada al estudio del comportamiento alimentario y la imagen corporal y la influencia de estas\r\nvariables en las conductas de autocuidado y salud. La Dra. Oda podr\u00e1 colaborar en la realizaci\u00f3n de las actividades lideradas por el Dr.\r\nS\u00e1nchez-Carracedo, tanto en cuanto a la investigaci\u00f3n, como en relaci\u00f3n a las actividades de divulgaci\u00f3n, especialmente potenciando el que\r\nestas puedan ser pertinentes a la realidad de nuestro pa\u00eds. (c) La tercera arista de esta red de colaboraci\u00f3n estar\u00eda asentada en el equipo\r\nCECA, conformado por los acad\u00e9micos e investigadores, Dr. Emilio Compte, Dra. Carla Ugarte, Dra. \u00a9 Fernanda D\u00edaz, y Dra. \u00a9 Paula Lizana,\r\nadem\u00e1s de nuestros ayudantes de pre y postgrado (de los programas Magister en Psicolog\u00eda Cl\u00ednica y Magister en Trastornos Alimentarios).\r\nEl equipo es liderado por Dra. Claudia Cruzat, desde la vasta experiencia con la que cuenta en el \u00e1mbito, especialmente mediante el\r\nliderazgo hist\u00f3rico del CECA, la investigaci\u00f3n en obesidad y trastornos de la conducta alimentaria en el pa\u00eds, la realizaci\u00f3n de actividades de\r\nformaci\u00f3n para profesionales de salud en este tipo de problem\u00e1ticas para profesionales de la salud del pa\u00eds, etc. Cabe se\u00f1alar que toda esta\r\nexperiencia se ver\u00eda significativamente enriquecida por esta red de colaboraci\u00f3n, especialmente de cara a la formulaci\u00f3n de futuros\r\nproyectos que permitan el desarrollar intervenciones y proyectos de investigaci\u00f3n en tem\u00e1ticas relacionadas con la obesidad en poblaci\u00f3n\r\ninfanto-juvenil, especialmente en vista de poder asegurar que estas l\u00edneas de trabajo tengan como foco principal el poder contribuir al\r\nabordaje no estigmatizante.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26444\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desarrollo l\u00ednea base para orientar estrategias de sustentabilidad y econom\u00eda circular con foco en salud de suelos hort\u00edcolas de la regi\u00f3n de O&#8217;higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26444\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26444\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto presentado a FIA por COAGRICAM en el que participo como asociado y cuyo objetivo es sentar la l\u00ednea base de los principales residuos agr\u00edcolas generados por la producci\u00f3n hort\u00edcola de la regi\u00f3n de O'Higgins, para hacer un tratamiento apropiado de estos y promover la circularidad y el manejo sostenible de los suelos de la regi\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Mayo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>CONAF XII Concurso del Fondo de Investigaci\u00f3n del Bosque Nativo (c\u00f3d: FIBN004\/21)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26477\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Evaluaci\u00f3n de la integridad ecol\u00f3gica bosques de Nothofagus macrocarpa\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26477\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26477\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Los bosques de Nothofagus macrocarpa se consideran relictos de las condiciones clim\u00e1ticas pasadas y de la historia de perturbaciones humanas. El actual estado de degradaci\u00f3n de los bosques de N. macrocarpa y su incierta resiliencia ante nuevas alteraciones de h\u00e1bitat humanas, como el cambio clim\u00e1tico o incendios forestales, y naturales hace que esta especie sea considerada en un estado de conservaci\u00f3n vulnerable. Sin embargo, esta definici\u00f3n de estado de conservaci\u00f3n carece de un an\u00e1lisis que integre las modificaciones de procesos ecol\u00f3gicos producto del potencial efecto de futuras condiciones clim\u00e1ticas y de las alteraciones humanas. En este proyecto buscamos desarrollar una evaluaci\u00f3n de la integridad ecol\u00f3gica de los bosques de N. macrocarpa en un contexto de alteraci\u00f3n de h\u00e1bitat producto del uso humano, sequ\u00edas pasadas y futuro cambio clim\u00e1tico. El m\u00e9todo propuesto permitir\u00e1 estandarizar una evaluaci\u00f3n que sintetice umbrales y curvas de respuesta de agentes de estr\u00e9s sobre las poblaciones de N. macrocarpa producto de la alteraci\u00f3n de h\u00e1bitat. Finalmente, generaremos instancias de di\u00e1logo y difusi\u00f3n de los hallazgos sistematizados de N. macrocarpa con comunidades locales y diversos actores gubernamentales, que ayuden a actualizar las bases normativas de la ley forestal en Chile.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Marzo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26479\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Restauraci\u00f3n ecol\u00f3gica en vegetaci\u00f3n xerof\u00edtica: uso de bioindicadores clave para evaluar el \u00e9xito de proyectos a corto plazo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26479\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26479\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El Cambio Global est\u00e1 alterando la composici\u00f3n y estructura original de los ecosistemas naturales, generando degradaci\u00f3n y fragmentaci\u00f3n a nivel mundial, especialmente en regiones vulnerables como las mediterr\u00e1neas. Bajo este escenario, la restauraci\u00f3n ecol\u00f3gica se ha tornado clave para la conservaci\u00f3n y recuperaci\u00f3n de ecosistemas con altos niveles de fragmentaci\u00f3n y perturbaci\u00f3n, como es el caso de las formaciones vegetacionales xerof\u00edticas de Chile central. Por ejemplo, la cuenca del r\u00edo Petorca, regi\u00f3n de Valpara\u00edso, est\u00e1 pasando por una sequ\u00eda hist\u00f3rica, adem\u00e1s de presentar altas tasas de sustituci\u00f3n de formaciones xerof\u00edticas por cultivos frutales. Por esto, los proyectos de restauraci\u00f3n ecol\u00f3gica en este tipo de vegetaci\u00f3n resultan un desaf\u00edo permanente, debido principalmente por la escasa informaci\u00f3n existente. Este desaf\u00edo aumenta al tratarse de iniciativas en la precordillera andina, que es justamente donde es necesario recuperar y aumentar las funciones ecosist\u00e9micas degradadas como la provisi\u00f3n de carbono y agua, el control de erosi\u00f3n, el h\u00e1bitat de especies, y biodiversidad, entre otros. Experiencias previas en restauraci\u00f3n se han centrado principalmente en plantar especies arb\u00f3reas, sin considerar la resiliencia de las \u00e1reas degradadas. La presente propuesta busca evaluar el \u00e9xito de la restauraci\u00f3n activa-pasiva en formaciones xerof\u00edticas a corto plazo en una cuenca altamente perturbada por cultivos agr\u00edcolas, bas\u00e1ndose en la capacidad de resiliencia de las \u00e1reas degradadas, para as\u00ed maximizar el potencial de recuperaci\u00f3n natural del ecosistema. Primero (obj 1), se realizar\u00e1 un diagn\u00f3stico del estado de las formaciones xerof\u00edticas de la cuenca del R\u00edo Petorca mediante una combinaci\u00f3n de datos satelitales, clasificando \u00e1reas xerof\u00edticas de acuerdo al nivel degradaci\u00f3n e identificando \u00e1reas productoras de semillas que ser\u00e1n usadas como ecosistemas de referencia, y as\u00ed definir \u00e1reas prioritarias a restaurar. Adem\u00e1s, se incluir\u00e1 la participaci\u00f3n actores relevantes desde el inicio del proyecto, con la finalidad de generar alianzas de mutuo beneficio, as\u00ed como tambi\u00e9n una retroalimentaci\u00f3n de los sitios con necesidad de restauraci\u00f3n y las metodolog\u00edas propuestas de restauraci\u00f3n. Finalmente, en esta etapa se seleccionar\u00e1 un sitio prioritario de restaurar y su ecosistema de referencia. Segundo (obj 2), se realizar\u00e1 un an\u00e1lisis comparativo entre los sitios seleccionados (degradado y referencia) mediante indicadores basados en estudios prospectivos y retrospectivos de la vegetaci\u00f3n, con objetivo de evaluar la resiliencia de las funciones ecosist\u00e9micas (principalmente cobertura, productividad, biodiversidad y eficiencia de uso del agua). Se realizar\u00e1 una caracterizaci\u00f3n prospectiva utilizando vuelos de dron y el monitoreo de parcelas fitosociol\u00f3gicas de estructura, diversidad y regeneraci\u00f3n de la vegetaci\u00f3n en todos sus h\u00e1bitos de vida. En paralelo se realizar\u00e1 un estudio retrospectivo para estudiar la variaci\u00f3n espacio-temporal en el crecimiento, acumulaci\u00f3n de carbono y uso eficiente del agua trav\u00e9s de estudios dendrocronol\u00f3gicos. Tercero (obj 3), con la informaci\u00f3n generada por los objetivos 1 y 2, se instalar\u00e1n y monitorear\u00e1n ensayos de restauraci\u00f3n ecol\u00f3gica ubicados espacialmente de manera estrat\u00e9gica, buscando la conexi\u00f3n de fragmentos y\/o remanentes naturales, basados en cuatro tratamientos: (i) Restauraci\u00f3n Activa (RAc: aislamiento del \u00e1rea, obras de conservaci\u00f3n de suelo, y reintroducci\u00f3n de especies arb\u00f3reas, arbustivas, herb\u00e1ceas y suculentas); (ii) Restauraci\u00f3n Asistida (RAs:  aislamiento del \u00e1rea y obras de conservaci\u00f3n de suelo); (iii) Restauraci\u00f3n pasiva (RP: aislaci\u00f3n del \u00e1rea); y (iv) control (tratamiento sin intervenci\u00f3n en sitio de referencia pr\u00f3ximos al sitio degradado). Para evaluar el \u00e9xito de los tratamientos de restauraci\u00f3n, se comparar\u00e1n los siguientes indicadores funcionales: (i) estructura, diversidad flor\u00edstica y par\u00e1metros ecofisiol\u00f3gicos; (ii) abundancia y biodiversidad de insectos bioindicadores; (iii) caracter\u00edsticas f\u00edsico-qu\u00edmicas del suelo y compactaci\u00f3n; (iv) condiciones microclim\u00e1ticas. Para poder analizar todos los indicadores bajo una misma variable respuesta, se evaluar\u00e1 la resiliencia a corto plazo de los tres tratamientos de restauraci\u00f3n a partir del porcentaje de cambio en cada indicador respecto al tratamiento control. Finalmente, se validar\u00e1 la informaci\u00f3n generada por el proyecto y su aporte a la Ley 20.283 mediante la participaci\u00f3n de los actores clave identificados anteriormente, buscando la transferencia, retroalimentaci\u00f3n y discusi\u00f3n entre el conocimiento cient\u00edfico y la percepci\u00f3n comunitaria (obj 4). Se espera que los resultados sirvan de base para el manejo, conservaci\u00f3n, restauraci\u00f3n y adaptaci\u00f3n de la vegetaci\u00f3n en tierras secas altamente degradadas frente a las amenazas del cambio global.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Junio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26488\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            A multi-scale drought observatory for Chile: an early warning system to mitigate agricultural and ecological impacts.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26488\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26488\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Since 2010, central Chile is experiencing a multi-dimensional crisis due to the pervasive impacts of the ongoing mega drought. Political institutions and stakeholders have responded reactively to socio-economic crises associated with the mega drought as they emerge (particularly in the agricultural and health sectors). While governments should move towards risk-based management (Wilhite et al. 2014), they require robust decision making tools to facilitate the transition. One such tool are early warning systems (EWS), which aim to reduce vulnerability and to improve response capacity of people at risk. However, the current observatory developed for Chile, While Chile current has the Chilean Agroclimatic Observatory (Verbist et al., 2016), was mainly designed for scientific purposes and has a poor user experience (UX). To this endwe propose the development of a multi-scale drought observatory for Chile that will help mitigate agricultural and ecological impacts. Using a macrosystems perspective (Heffernan et al. 2014), this observatory will integrate global climate and land satellite data with in-situ measurements from national weather stations. It will have two main components: i) monitoring climate and land variables and their impacts on agricultural and socio-ecological systems, and ii) a drought early warning system (DEWS). The drought monitoring and DEWS platforms will target three user groups \u0096 the general public, decision makers , and the scientific community \u0096 and will comply with FAIR data principles (Wilkinson et al. 2016), to enhance usability of all products. We will monitor drought-related variables at two spatial scales: the national scale (Fig. 1a) and at ii) the local scale for which we selected the Aconcagua watershed (Fig 1b). Local-scale measurements will also be used to validate and improve drought monitoring at the national scale. We selected this watershed for two reasons: i) it has been highly impacted by drought (Fig. 2c, showing the extreme drought conditions across the watershed), which have triggered several conflicts this year (2021) between agricultural interests and groups concerned with access to drinking water; and ii) this watershed will provide a preview of the future for other watersheds that have yet to experience the evolving, multi-dimensional impacts of similarly extreme droughts.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26489\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Assessing the resilience of mediterranean-type ecosystems of Chile to projected drought conditions: a multi-scale approach\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26489\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26489\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Anthropogenic climate change (global change) has caused widespread negative impacts on the vitality and natural dynamics of forest ecosystems across different biomes worldwide. Such impacts are forecast to continue throughout the 21st Century, with Mediterranean-type ecosystems (MTE) being one of the most vulnerable worldwide. MTE are a global conservation priority owing to their high biodiversity, endemism and, carbon and water cycling. In particular, there are significant concerns and uncertainties about the future of tree-dominated MTEs given their vulnerability to global change and, therefore, the consequent likelihood of rapid changes in species distribution. I will assess the response and adaptation of the only Mediterranean forest ecosystems in South America to current and forecasted climate change along biogeographic gradients from sclerophyllous forest to relict mountain in central Chile, using a multi-scale approach, from shrubs to tall trees, and from seeds to ecosystem. This information will allow us to understand the stability of the trailing edge and the potential threats due to the upward migration of other species under global warming in Chilean MTE forest. To achieve these goals, I will exploit multidisciplinary approaches based on hydrology, remote sensing, dendrochronology, ecology, genetic and plant physiology, combining field, laboratory and experimental studies, with the purpose of forecasting forest. Considering that climate change is expected to drive abrupt nonlinear changes throughout the 21st century. I will include analytical approaches that can accommodate these non-linear relationships such as process-based models, non-stationary time-series models and structural equation modeling, as they can support a physiological approach that can robustly assess the forest productivity responses to future climate variability. This proposal will involve three approaches to forecasting forest resilience at different ecological scales: (i) forest-scale research to assess and predict canopy decline and change in foliar phenology using remote sensing and model-based climatic projections using in situ and ex situ data (Obj 1);  population-based study assessing the current and future resilience of tree populations using demographic rates, ecophysiological indicators and genetic traits (Obj 2); regeneration-based study to investigate mechanisms of local adaptation in early life stages and potential for persistence of populations, using plant-growth chambers to simulate current and future climate condition in Chile\u0092s MTE (Obj 3). Finally, a multivariate analysis to determine the relative resilience of forests based on information of three previous approach will be assess (Objective 4). Each projected approach will be transformed to predict change percentage, and thus, forecasted resilience rate by short-intermediate (2030-2065) and long term (2065-2100), considering the same weight of each approach. This proposal is a pioneer in global change research in ecology and biogeography due to its focus on possible migration from sclerophyllous trees to mountain forest in South American MTE. Findings will enable us to identify and predict species- and population-level resilience in the face of global climate change to inform priorities for conservation, mitigation and adaptation.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Diciembre 2029<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26516\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Centro de Modelamiento Matem\u00e1tico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26516\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26516\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El Centro de Modelamiento Matem\u00e1tico (CMM) es un centro cient\u00edfico l\u00edder en Chile para la investigaci\u00f3n y aplicaciones de las matem\u00e1ticas. Fue inaugurado en abril del 2000 y forma parte de la Facultad de Ciencias F\u00edsicas y Matem\u00e1ticas (FCFM) de la Universidad de Chile, en la que se encuentra la principal y m\u00e1s antigua escuela de ingenier\u00eda del pa\u00eds. Su objetivo es crear nuevas matem\u00e1ticas y utilizarlas para resolver problemas provenientes de otras ciencias, la industria y las pol\u00edticas p\u00fablicas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Diciembre 2029<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26569\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Centro de Modelamiento Matem\u00e1tico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26569\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26569\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El Centro de Modelamiento Matem\u00e1tico (CMM) es un centro cient\u00edfico l\u00edder en Chile para la investigaci\u00f3n y aplicaciones de las matem\u00e1ticas. Fue inaugurado en abril del 2000 y forma parte de la Facultad de Ciencias F\u00edsicas y Matem\u00e1ticas (FCFM) de la Universidad de Chile, en la que se encuentra la principal y m\u00e1s antigua escuela de ingenier\u00eda del pa\u00eds. Su objetivo es crear nuevas matem\u00e1ticas y utilizarlas para resolver problemas provenientes de otras ciencias, la industria y las pol\u00edticas p\u00fablicas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Diciembre 2029<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26646\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Centro de Modelamiento Matem\u00e1tico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26646\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26646\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El Centro de Modelamiento Matem\u00e1tico (CMM) es un centro cient\u00edfico l\u00edder en Chile para la investigaci\u00f3n y aplicaciones de las matem\u00e1ticas. Fue inaugurado en abril del 2000 y forma parte de la Facultad de Ciencias F\u00edsicas y Matem\u00e1ticas (FCFM) de la Universidad de Chile, en la que se encuentra la principal y m\u00e1s antigua escuela de ingenier\u00eda del pa\u00eds. Su objetivo es crear nuevas matem\u00e1ticas y utilizarlas para resolver problemas provenientes de otras ciencias, la industria y las pol\u00edticas p\u00fablicas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Febrero 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26705\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Commutation principles and some variational problems involving spectral sets and functions on various invariant systems\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26705\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26705\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The project deals with commutation principles in Euclidean Jordan Algebras, Normal Decomposition systems and Fan-Theobald-von Newman systems. It propose to deal with the generalization of these principles and the application to variational analysis and the Marcus-de Oliveira determinantal conjecture.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26942\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Nuevos m\u00e9todos computacionales para caracterizar la arquitectura gen\u00e9tica de reordenamientos gen\u00f3micos complejos en c\u00e1nceres Chilenos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26942\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26942\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El c\u00e1ncer es la segunda causa de muerte en la poblaci\u00f3n Chilena y se proyecta que en diez a\u00f1os ser\u00e1 la primera causa de muerte en el pa\u00eds. A nivel regional, la regi\u00f3n de O Higgins es la que presenta la mayor incidencia de muertes por c\u00e1ncer. Actualmente, Chile invierte alrededor del 1% del PIB en atenci\u00f3n y tratamiento del c\u00e1ncer. Es indispensable y urgente comenzar a caracterizar molecularmente los c\u00e1nceres prevalentes de la poblaci\u00f3n Chilena pues esto permitir\u00e1 integrar informaci\u00f3n que impactar\u00e1 las decisiones cl\u00ednicas permitiendo la implementaci\u00f3n de tratamientos espec\u00edficos para los pacientes. El estudio gen\u00f3mico y molecular de sistemas biol\u00f3gicos complejos, como el desarrollo y progresi\u00f3n del c\u00e1ncer, requieren del desarrollo de nuevos algoritmos y modelos te\u00f3ricos para analizar e interpretar datos gen\u00f3micos complejos (big- data). El principal objetivo del laboratorio de gen\u00f3mica computacional que instalar\u00e9 en el instituto de ciencias de la ingenier\u00eda de la Universidad de O Higgins ser\u00e1 desarrollar investigaci\u00f3n de vanguardia entorno al dise\u00f1o y aplicaci\u00f3n de nuevos algoritmos y tecnolog\u00edas \u00f3micas para estudiar la arquitectura gen\u00f3mica de c\u00e1nceres prevalentes de la poblaci\u00f3n Chilena. La meta a largo plazo es trasladar estas tecnolog\u00edas a la pr\u00e1ctica cl\u00ednica e impulsar la implementaci\u00f3n de programas de medicina de precisi\u00f3n enfocados en el tratamiento y prevenci\u00f3n del c\u00e1ncer en nuestro pa\u00eds y regi\u00f3n. Un segundo objetivo es impulsar y liderar investigaci\u00f3n multidisciplinaria en tem\u00e1ticas de salud, agroindustria y miner\u00eda, sectores cr\u00edticos a desarrollar en la regi\u00f3n de O'Higgins. Finalmente, el laboratorio de gen\u00f3mica computacional contribuir\u00e1 a la formaci\u00f3n de capital humano avanzado en \u00e1reas asociadas a la gen\u00f3mica, bioinform\u00e1tica y biolog\u00eda computacional.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1221029<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Marzo 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26944\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            New computational algorithms to elucidate the genetic architecture and functional impact of large-scale rearrangement in prevalent Chilean cancers.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26944\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26944\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The Chilean government recently launched the national cancer plan to increase survival rates and reduce cancer incidence, which is projected to become the first cause of death in the Chilean population. Only in 2020, more than 55,000 new cases of cancer were registered. Therefore, starting the molecular characterization of the prevalent cancers of the Chilean population is urgent since this can inform therapeutic decisions and thus promote more specific treatments for patients, positively impacting survival rates and prevention.  \r\nDue to the constant improvement of sequencing technologies, cancer research increasingly relies on the interpretation and analysis of high-dimensional genomic data. Genomic cancer analysis has revealed that the mutation repertoire of tumors is vast and goes from single nucleotide variants to whole-genome duplications. Structural variants (SVs) and copy number alterations are significant drivers of cancer proliferation and represent the building blocks of complex mutational processes involving the rearrangement of large genomic regions. These complex genomic rearrangements have functional consequences (e.g., gene fusion formation, inactivation of tumor suppressor) and have been associated with lower survival and poor response to immunotherapy. The patterns of small somatic variants have been well studied and characterized in human cancers. However, the genetic architecture and functional consequences of complex genomic rearrangements, despite their clinical significance, still need to be explored due to algorithmic and technological limitations. Therefore, the aims of this proposal are first to develop novel computational tools to fully characterize the genetic architecture of complex genomic rearrangements and second to study their functional impact on tumor gene expression programs through the lens of a solid theoretical framework.\r\nMethodologically, the de novo assembly of genomes is the only approach that allows a complete and unbiased characterization of all genomic alterations. Recently, we developed WENGAN, a new algorithm for the ultrafast, accurate, and complete de novo reconstruction of human genomes combining short and long reads technologies. Initial validation of WENGAN for de novo reconstruction of cancer genomes enabled the discovery of a large degree of tumor genomic reorganization with thousands of SVs. The latter remains elusive when using alternative algorithms and technologies. Therefore, this experience represents a solid foundation for developing this proposal. We will work with the following specific objectives: 1) Develop efficient algorithms to reconstruct haplotype-resolved genomes; 2) combine haplotype-resolved genomes and variation graphs with building complete structural variant maps of tumors; 3) study the functional impact of complex SVs at the single-cell level; and 4) Infer from multi-omic data the tumor tasks (trade-offs) using the multi-task evolution theory. We have assembled a multidisciplinary network of national and international (France and Germany) experts in algorithms, sequencing technologies, and cancer genomics to develop these objectives. Additionally, we compromise the mentoring and training of undergraduate and magister students by offering thesis topics directly related to the proposal's goals.\r\nIn summary, we propose an approach that integrates the development of new computational algorithms, a solid theoretical framework, and the generation of state-of-the-art multi-omic data to study the genetic architecture and functional impact of large-scale genomic rearrangements in a prevalent Chilean cancer. The project will deliver, in four years, the first haplotype-resolved Chilean genome, the first graph reference of Chilean individuals, and the first multi-omic characterization of a prevalent Chilean cancer.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Marzo 2032<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26946\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            CUARTO CONCURSO NACIONAL DE FINANCIAMIENTO BASAL PARA CENTROS CIENT\u00cdFICOS Y TECNOL\u00d3GICOS DE EXCELENCIA \u0096 PIA: Center for Mathematical Modeling.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26946\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26946\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Center for Mathematical Modeling.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26987\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Linchamientos y Cultura Jur\u00eddica Popular en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26987\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26987\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Materia Espec\u00edfica: El proyecto busca comprender la conciencia jur\u00eddica de los legos que respaldan los linchamientos y, de ser pertinente, dar cuenta de la configuraci\u00f3n de alienaci\u00f3n legal que atraviesa dicha conciencia jur\u00eddica.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1220066<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2022 - Febrero 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27102\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27102\" aria-expanded=\"false\" aria-controls=\"collapse-27102\">\n                                            Pr\u00e1cticas art\u00edsticas de mediaci\u00f3n con comunidades: desaf\u00edos para expandir el rol social de las artes en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27102\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27102\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto \u0093Pr\u00e1cticas Art\u00edsticas de Mediaci\u00f3n con Comunidades: Desaf\u00edos para Expandir el Rol Social de las Artes en Chile\u0094, desarrollado bajo el programa Fondecyt Regular n\u00b0 1220066, tuvo como objetivo general comprender c\u00f3mo las pr\u00e1cticas art\u00edsticas de mediaci\u00f3n contribuyen a abordar problem\u00e1ticas socioculturales, generando estrategias que expandan el rol social de las artes en diversos contextos y comunidades del pa\u00eds&#8203;.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ICN2021_023<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Febrero 2022 - Febrero 2032<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26615\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26615\" aria-expanded=\"false\" aria-controls=\"collapse-26615\">\n                                            Instituto Milenio en Amon\u00edaco Verde como Vector Energ\u00e9tico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26615\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26615\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetivo principal de MIGA (Millenium Institute in Green Ammonia) es consolidar un espacio interdisciplinario de excelencia cient\u00edfica promoviendo la formaci\u00f3n de recursos humanos avanzados, conocimiento y tecnolog\u00eda en temas relacionados con la producci\u00f3n sostenible y el uso del amoniaco como vector energ\u00e9tico.\r\n\r\nLa misi\u00f3n de MIGA es abordar este desaf\u00edo con un enfoque interdisciplinario que acorte las brechas tecnol\u00f3gicas actuales, avanzando en el conocimiento y la tecnolog\u00eda, generando capacitaci\u00f3n interdisciplinaria en el \u00e1rea para nuevos investigadores, contribuyendo a la instalaci\u00f3n de econom\u00edas basadas en energ\u00edas limpias para Chile y la comunidad internacional. MIGA es conceptualizado en cinco \u00e1reas de investigaci\u00f3n interdisciplinarias e interrelacionadas:\r\n\r\n1. Producci\u00f3n electroqu\u00edmica de NH3\r\n2. Producci\u00f3n de H2 a partir de electr\u00f3lisis de NH3 \r\n3. Dise\u00f1o y prototipos de pilas de combustible de NH3 \r\n4. Procesos de corrosi\u00f3n y protecci\u00f3n \r\n5. Econom\u00eda del amoniaco[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Febrero 2022 - Diciembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>STINT (Swedish Foundation for International Cooperation in Research and Higher Education)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27128\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Cryotourism in a warming world: Co-exploring glacier and snow-based tourism development in southern and northern peripheries\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27128\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27128\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto examina las transformaciones del turismo basado en nieve y glaciares en un contexto de cambio clim\u00e1tico acelerado. A partir de un enfoque comparativo entre periferias del norte y del sur global, la investigaci\u00f3n analiza c\u00f3mo el retroceso de cri\u00f3sferas est\u00e1 reconfigurando las oportunidades, pr\u00e1cticas y narrativas del turismo en territorios dependientes de estos recursos. El proyecto combina perspectivas de la geograf\u00eda humana, los estudios del turismo y la sostenibilidad para co-explorar, junto a actores locales y acad\u00e9micos, nuevas trayectorias de desarrollo tur\u00edstico frente a escenarios de incertidumbre ambiental. Metodol\u00f3gicamente, se basa en el intercambio internacional, la colaboraci\u00f3n interdisciplinaria y la generaci\u00f3n conjunta de conocimiento, con el objetivo de comprender las tensiones entre adaptaci\u00f3n, conservaci\u00f3n y desarrollo econ\u00f3mico. Los resultados buscan aportar a debates te\u00f3ricos sobre turismo en contextos de cambio global, as\u00ed como a la formulaci\u00f3n de estrategias m\u00e1s resilientes e inclusivas para territorios perif\u00e9ricos afectados por la p\u00e9rdida de hielo y nieve.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2022 - Enero 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26468\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Micro-redes el\u00e9ctricas para una agricultura energ\u00e9ticamente sustentable\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26468\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26468\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En particular, el proyecto instalar\u00e1 y desarrollar\u00e1 en la regi\u00f3n de O\u0092Higgins capacidades\r\nhumanas avanzadas y fortalecer\u00e1 la cooperaci\u00f3n internacional en tem\u00e1ticas\r\nrelacionadas con el uso de micro-redes en agricultura. Tambi\u00e9n, se instalar\u00e1 un proyecto\r\npiloto de micro-red el\u00e9ctrica aplicado en cultivos bajo invernadero.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2022 - Enero 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26597\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Micro-redes el\u00e9ctricas para una agricultura energ\u00e9ticamente sustentable\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26597\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26597\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En particular, el proyecto instalar\u00e1 y desarrollar\u00e1 en la regi\u00f3n de O\u0092Higgins capacidades\r\nhumanas avanzadas y fortalecer\u00e1 la cooperaci\u00f3n internacional en tem\u00e1ticas\r\nrelacionadas con el uso de micro-redes en agricultura. Tambi\u00e9n, se instalar\u00e1 un proyecto\r\npiloto de micro-red el\u00e9ctrica aplicado en cultivos bajo invernadero.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2022 - Enero 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26873\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Micro-redes el\u00e9ctricas para una agricultura energ\u00e9ticamente sustentable\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26873\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26873\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En particular, el proyecto instalar\u00e1 y desarrollar\u00e1 en la regi\u00f3n de O\u0092Higgins capacidades\r\nhumanas avanzadas y fortalecer\u00e1 la cooperaci\u00f3n internacional en tem\u00e1ticas\r\nrelacionadas con el uso de micro-redes en agricultura. Tambi\u00e9n, se instalar\u00e1 un proyecto\r\npiloto de micro-red el\u00e9ctrica aplicado en cultivos bajo invernadero.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2022 - Junio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26560\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Understanding the cardioceptive processing in the auditory perception: A EEG study\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26560\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26560\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The project aims to study the cardiac cycle's impact on healthy adults' brain responses and auditory perception. Using electroencephalogram and electrocardiogram recordings, we compare the neuronal responses to heartbeats in response to auditory stimulation in the different phases of the cardiac cycle. We evaluate cardioceptive measures to establish relationships between neuronal activity and sensory and behavioral parameters.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2022 - Diciembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26298\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Evaluaci\u00f3n del riesgo de aflatoxinas en ni\u00f1os menores de dos a\u00f1os por el consumo de l\u00e1cteos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26298\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26298\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Actualmente no existe informaci\u00f3n de exposici\u00f3n a micotoxinas en Chile en ni\u00f1os por consumo de l\u00e1cteos. El proyecto Puente, tiene como objetivo evaluar el riesgo asociado a la exposici\u00f3n a aflatoxina por el consumo de l\u00e1cteos en infantes chilenos de 2 a\u00f1os o menos.\r\nLos objetivos espec\u00edficos son:\r\n1. Medir la ocurrencia y concentraci\u00f3n de aflatoxina M1 en l\u00e1cteos consumidos por menores de 2 a\u00f1os en Chile.\r\n2. Evaluar el riesgo a aflatoxina B1 en lactantes debido al consumo de l\u00e1cteos.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26447\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Sistema articulado de investigaci\u00f3n en cambio clim\u00e1tico y sustentabilidad de zonas costeras de Chile.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26447\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26447\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2022 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25985\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Sistema Articulado de Investigaci\u00f3n en Cambio Clim\u00e1tico y Sustentabilidad de Zonas Costeras de Chile (URO RED21992)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25985\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25985\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Sistema Articulado de Investigaci\u00f3n en Cambio Clim\u00e1tico y Sustentabilidad de Zonas Costeras de Chile CUECH\/RISUE RED21992[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Corporaci\u00f3n de Fomento de la Producci\u00f3n - CORFO<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26012\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            DESARROLLO DE OLIGONUCLEOTIDOS ANTISENTIDO (ASO) COMO NUEVOS INSECTICIDAS CONTRA PLAGAS DE INTERES\u0094,\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26012\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26012\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetivo general del proyecto es el desarrollo del uso de un formulado en base a \u00e1cidos nucleicos de DNA (oligos) de genes asociados a control de procesos biol\u00f3gicos asociados a citoesqueleto. El uso de estos formulados tiene un gran potencial debido a su baja residualidad y alta especificidad.\r\n\r\nProyecto se realiza en conjunto con la Universidad de O'higgins y la Universidad Cat\u00f3lica liderado por la empresa APOL[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ACT210060<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26173\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Firing: Multiscale effects of extreme forest fires on erosion, water, and biogeochemical cycles in natural and managed forest soils\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26173\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26173\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"].[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2022 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26174\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Sistema Articulado de Investigaci\u00f3n en Cambio Clim\u00e1tico y Sustentabilidad de Zonas Costeras de Chile (URO RED21992)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26174\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26174\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Sistema Articulado de Investigaci\u00f3n en Cambio Clim\u00e1tico y Sustentabilidad de Zonas Costeras de Chile CUECH\/RISUE RED21992[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2022 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26279\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Sistema Articulado de Investigaci\u00f3n en Cambio Clim\u00e1tico y Sustentabilidad de Zonas Costeras de Chile (URO RED21992)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26279\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26279\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Sistema Articulado de Investigaci\u00f3n en Cambio Clim\u00e1tico y Sustentabilidad de Zonas Costeras de Chile CUECH\/RISUE RED21992[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2022 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26320\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Sistema Articulado de Investigaci\u00f3n en Cambio Clim\u00e1tico y Sustentabilidad de Zonas Costeras de Chile (URO RED21992)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26320\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26320\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Sistema Articulado de Investigaci\u00f3n en Cambio Clim\u00e1tico y Sustentabilidad de Zonas Costeras de Chile CUECH\/RISUE RED21992[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> CP21-P134<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2022 - Diciembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26321\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Volando en El Tiempo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26321\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26321\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]\u0093Volando en El Tiempo\u0094 es un cuento para ni\u00f1os y ni\u00f1as (de 3 a 9 a\u00f1os) que se presenta en un novedoso formato: calendario con cuento de pared. La historia narra el viaje de una lora Tricahue desde la Regi\u00f3n de O\u0092Higgins a 12 lugares del pa\u00eds, donde conoce e interact\u00faa con diferentes fen\u00f3menos meteorol\u00f3gicos y climatol\u00f3gicos. El producto unir\u00e1 relatos cortos junto a ilustraciones y tendr\u00e1 una p\u00e1gina para cada mes, la identificaci\u00f3n de las cuatro estaciones del a\u00f1o y actividades\/preguntas para fomentar la observaci\u00f3n de las ni\u00f1as y ni\u00f1os del tiempo meteorol\u00f3gico. \r\nLa creaci\u00f3n de este producto contempla un equipo multidisciplinario con experiencia en divulgaci\u00f3n de la ciencia, ciencias atmosf\u00e9ricas y en divulgaci\u00f3n con ni\u00f1os y ni\u00f1as. Se repartir\u00e1n 1.500 unidades de los calendarios y adem\u00e1s se propone crear un formato digital descargable del calendario y otro del cuento (junto con un audio-cuento) para poder difundir en otros p\u00fablicos. \r\nEsperamos despertar la curiosidad de las ni\u00f1as y ni\u00f1os que viven en Chile sobre las Ciencias Atmosf\u00e9ricas y Cambio Clim\u00e1tico una manera simple: mirando un calendario y pudiendo observar por la ventana o saliendo a ver el cielo y as\u00ed conocer sobre el tiempo a trav\u00e9s del vuelo que hace la lora.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2022 - Abril 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Corporaci\u00f3n de Fomento de la Producci\u00f3n - CORFO<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26341\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desarrollo Agr\u00edcola Integral del Secano Interior de la Regi\u00f3n de O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26341\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26341\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Comprende la contrataci\u00f3n de un Estudio de validaci\u00f3n productiva, vinculada al establecimiento de nuevos huertos y cultivos, manejos agron\u00f3micos y creaci\u00f3n de fichas t\u00e9cnicas por cada rubro con potencial identificado.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2022 - Marzo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>CODELCO<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26370\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Autoecolog\u00eda de Pristidactylus valeriae y Programa de Educaci\u00f3n Ambiental \u0093Plan de Difusi\u00f3n de Fauna Sensible\u0094,\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26370\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26370\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Dentro de los compromisos ambientales adquiridos por la Divisi\u00f3n El Teniente (DET) en la RCA 16 correspondiente a la construcci\u00f3n del Nuevo Campamento Car\u00e9n, se\r\nestableci\u00f3 como Compromiso Ambiental Voluntario por parte de DET. Este consiste en realizar la promoci\u00f3n de investigaci\u00f3n y educaci\u00f3n ambiental en las comunas de intervenci\u00f3n del proyecto de las especies sensibles reconocidas.\r\nEn virtud del convenio UOH-DET, ejecutar\u00e9 una investigaci\u00f3n relativa a la especie Pristidactylus valeriae  asociado a un plan de actividades de educaci\u00f3n ambiental denominado \u0093Plan de Difusi\u00f3n de Fauna Sensible\u0094, donde ambas iniciativas tributaran a la Secretar\u00eda Regional Ministerial del Medio Ambiente de la Regi\u00f3n Metropolitana de Santiago.\r\n\r\nEn este proyecto, soy la responsable del dise\u00f1o y ejecuci\u00f3n (ICA3\/UOH) junto a mis co-investigadores. Como coordinador del convenio UOH-DET participa Sim\u00f3n Cox, quien tambi\u00e9n colaborar\u00e1 durante la ejecuci\u00f3n del proyecto.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2022 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26446\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Sistema Articulado de Investigaci\u00f3n en Cambio Clim\u00e1tico y Sustentabilidad de Zonas Costeras de Chile (URO RED21992)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26446\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26446\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Sistema Articulado de Investigaci\u00f3n en Cambio Clim\u00e1tico y Sustentabilidad de Zonas Costeras de Chile CUECH\/RISUE RED21992[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 2195<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26734\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortalecimiento de la colaboraci\u00f3n y asociatividad entre los actores regionales y la Universidad de O\u0092Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26734\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26734\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]\u0093Fortalecimiento de la colaboraci\u00f3n y asociatividad entre los actores regionales y la Universidad de O\u0092Higgins\u0094\r\nObjetivo: Fortalecer la colaboraci\u00f3n y asociatividad entre los actores regionales y la Universidad, a trav\u00e9s de intervenciones innovadoras integrales, que permitan avanzar en soluci\u00f3n a problem\u00e1ticas complejas a partir de una \u00f3ptima multidisciplinaria.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2022 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26772\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Sistema Articulado de Investigaci\u00f3n en Cambio Clim\u00e1tico y Sustentabilidad de Zonas Costeras de Chile (URO RED21992)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26772\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26772\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Sistema Articulado de Investigaci\u00f3n en Cambio Clim\u00e1tico y Sustentabilidad de Zonas Costeras de Chile CUECH\/RISUE RED21992[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2022 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26896\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Sistema Articulado de Investigaci\u00f3n en Cambio Clim\u00e1tico y Sustentabilidad de Zonas Costeras de Chile (URO RED21992)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26896\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26896\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Sistema Articulado de Investigaci\u00f3n en Cambio Clim\u00e1tico y Sustentabilidad de Zonas Costeras de Chile CUECH\/RISUE RED21992[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2022 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26904\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Sistema Articulado de Investigaci\u00f3n en Cambio Clim\u00e1tico y Sustentabilidad de Zonas Costeras de Chile (URO RED21992)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26904\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26904\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Sistema Articulado de Investigaci\u00f3n en Cambio Clim\u00e1tico y Sustentabilidad de Zonas Costeras de Chile CUECH\/RISUE RED21992[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2022 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26940\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Sistema Articulado de Investigaci\u00f3n en Cambio Clim\u00e1tico y Sustentabilidad de Zonas Costeras de Chile (URO RED21992)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26940\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26940\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Sistema Articulado de Investigaci\u00f3n en Cambio Clim\u00e1tico y Sustentabilidad de Zonas Costeras de Chile CUECH\/RISUE RED21992[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Estatal de Investigaci\u00f3n (AEI) de Espa\u00f1a<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26970\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Pensamiento algebraico en educaci\u00f3n infantil y educaci\u00f3n primaria\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26970\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26970\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]www.pensamientoalgebraico.es[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FSEQ210007<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2022 - Diciembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26931\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Breaking the current recharge paradigm in Central Chile: a deep borehole for Andean groundwater flows estimation\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26931\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26931\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The main aim of the present proposal is to assess, in the Western Andean Front, the magnitude and the spatiotemporal variability of deep groundwater flows and derived mountain block recharge using an original and direct collection of hydrogeological, lithological, and geophysical data. Specific objectives are:\r\n- Obj. 1: Assess the spatial variation at depth of the Abanico Formation hydraulic properties to improve the understanding of Western Andean Front fault systems and their impacts on the water transference to alluvial aquifers.\r\n- Obj. 2: Unravel the aquifer capacity of fractured rocks (i.e. Abanico Formation) and the critical zone extinction depth for groundwater flows and mountain block recharge mechanisms in the Western Andean Front of Central Chile.\r\n- Obj. 3: Estimate the mountain block recharge mechanisms regarding their quantitative (flow) and qualitative (hydrogeochemistry) aspects and assess the vulnerability of deep groundwater flows to shallow water-store variations caused by current and future hydroclimatic changes in the Western Andean Front.\r\nThe study of borehole core lithological and hydraulic properties, groundwater geochemical composition, flow rates, together with spring hydraulic and hydrogeochemistry behaviors will help to fill a gap of knowledge about deep groundwater flows originating from the Principal Cordillera. This deep borehole and derived original information will therefore be used as an \u0093eye\u0094 inside the deep Chilean Andes groundwater resources. Finally, it will be a useful observation point for multidisciplinary research due to the interest of national and international researchers to collect samples at depth and therefore will expand shared knowledge and national frontier research[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> URO21992<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26933\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Sistema articulado de investigaci\u00f3n en cambio clim\u00e1tico y sustentabilidad de zonas costeras de Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26933\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26933\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La sustentabilidad de Chile es un desaf\u00edo pa\u00eds en el cual deben interactuar diferentes actores de la sociedad. En la actualidad existe voluntad pol\u00edtica e inter\u00e9s al interior de las Universidades y el sector P\u00fablico-Privado para trabajar en la tem\u00e1tica de Sustentabilidad, a fin de dar respuestas con sustento cient\u00edfico y responsable a la sociedad. Un desaf\u00edo instalado a partir de la agenda de la Organizaci\u00f3n de las Naciones Unidas de fines de 2015, que incluye el establecimiento de 17 Objetivos de Desarrollo Sostenible (ODS), donde los pa\u00edses han adquirido un compromiso expl\u00edcito y real de crecimiento econ\u00f3mico, inclusi\u00f3n social y protecci\u00f3n ambiental, basados en la Sustentabilidad. En este contexto, el Consorcio de Universidades del Estado de Chile (CUECH), ha definido la sustentabilidad como uno de los temas prioritarios de estudio. As\u00ed a mediados de 2017 se origina la Red de Investigaci\u00f3n en Sustentabilidad de las Universidades del Estado (RISUE) para dar respuesta a los desaf\u00edos del desarrollo sustentable del pa\u00eds. En esta propuesta la RISUE se enfocar\u00eda en contribu\u00edr a los ODS 13 acci\u00f3n por el clima, 14 vida submarina, 15 vida de ecosistemas terrestres y 17 alianzas para lograr los objetivos. De este modo, la amplia distribuci\u00f3n geogr\u00e1fica de las universidades pertenecientes al CUECH posibilita que esta RISUE aborde la sustentabilidad con una mirada local y al mismo tiempo con una representatividad de todo el pa\u00eds. Desde fines de 2017 la RISUE ha realizado cuatro talleres, definiendo el establecimiento de tres grandes l\u00edneas de investigaci\u00f3n prioritarias: Sustentabilidad de Sistemas antr\u00f3picos, Sustentabilidad de Ecosistemas, y Caracterizaci\u00f3n y Proyecci\u00f3n del Clima en Chile. A partir de estas l\u00edneas prioritarias, la RISUE se plante\u00f3 una serie de objetivos que tuvieron un desarrollo variable debido a la crisis social y sanitaria del pa\u00eds y a la inexistencia de incentivos para participar en la RISUE.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FSEQ210007<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2022 - Diciembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27044\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Breaking the current recharge paradigm in Central Chile: a deep borehole for Andean groundwater flows estimation\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27044\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27044\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The main aim of the present proposal is to assess, in the Western Andean Front, the magnitude and the spatiotemporal variability of deep groundwater flows and derived mountain block recharge using an original and direct collection of hydrogeological, lithological, and geophysical data. Specific objectives are:\r\n- Obj. 1: Assess the spatial variation at depth of the Abanico Formation hydraulic properties to improve the understanding of Western Andean Front fault systems and their impacts on the water transference to alluvial aquifers.\r\n- Obj. 2: Unravel the aquifer capacity of fractured rocks (i.e. Abanico Formation) and the critical zone extinction depth for groundwater flows and mountain block recharge mechanisms in the Western Andean Front of Central Chile.\r\n- Obj. 3: Estimate the mountain block recharge mechanisms regarding their quantitative (flow) and qualitative (hydrogeochemistry) aspects and assess the vulnerability of deep groundwater flows to shallow water-store variations caused by current and future hydroclimatic changes in the Western Andean Front.\r\nThe study of borehole core lithological and hydraulic properties, groundwater geochemical composition, flow rates, together with spring hydraulic and hydrogeochemistry behaviors will help to fill a gap of knowledge about deep groundwater flows originating from the Principal Cordillera. This deep borehole and derived original information will therefore be used as an \u0093eye\u0094 inside the deep Chilean Andes groundwater resources. Finally, it will be a useful observation point for multidisciplinary research due to the interest of national and international researchers to collect samples at depth and therefore will expand shared knowledge and national frontier research[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2021 - Junio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26059\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Problem\u00e1ticas sobre identidades nacionales y regionales en la literatura para la infancia y adolescencia: intercambios acad\u00e9micos interdisciplinarios y propuestas did\u00e1cticas para el \u00e1mbito educacional (Proy. ANID)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26059\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26059\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Existe extensa evidencia en torno a la relevancia que la literatura producida para la infancia y adolescencia tiene en la conformaci\u00f3n, transmisi\u00f3n, validaci\u00f3n o subversi\u00f3n de imaginarios de identidades nacionales y regionales. Los children\u0092s literature studies han dado cuenta de las complejas relaciones entre los discursos literarios y fen\u00f3menos como la globalizaci\u00f3n, el colonialismo, el mestizaje, el imperialismo, los procesos modernizadores, la crisis medioambiental, los sentidos de pertenencia territorial, la constituci\u00f3n de una lengua nacional, los conceptos de raza, de ciudadan\u00eda e interculturalidad y su consecuente influencia en la cohesi\u00f3n social  de las naciones. Con el fin de aportar a esto \u00faltimo, potenciando valores como la igualdad, el respeto, el sano disenso y la colaboraci\u00f3n, este proyecto tiene como objetivo articular una red acad\u00e9mica interdisciplinaria y multilateral en torno a problem\u00e1ticas sobre identidades nacionales y regionales en la literatura para la infancia y la adolescencia. Esta red (Red Identidades, Literatura e Infancias\/Adolescencias) se articular\u00e1 entre la Universidad de O\u0092Higgins, la Universidad Cat\u00f3lica del Maule, la Universidad Aut\u00f3noma sede Temuco, Penn State University y University of Oklahoma. La red se mantendr\u00e1 por medio de un esquema de sesiones de trabajo multilateral en l\u00ednea (Taller Ampliado), de periodicidad mensual, por un a\u00f1o.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI 210023<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2021 - Abril 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26591\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Micro-redes el\u00e9ctricas para una agricultura energ\u00e9ticamente sustentable\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26591\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26591\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En la regi\u00f3n de O\u0092Higgins la agricultura es una actividad econ\u00f3mica relevante tanto a escala industrial como a peque\u00f1a escala familiar, representando un 26 % del empleo regional durante el per\u00edodo septiembre-diciembre 2019 (ODEPA, Bolet\u00edn de Empleo, Feb. 2020). Hoy en d\u00eda, esta actividad se ve afectada profundamente por el cambio clim\u00e1tico y sus efectos, como son por ejemplo: los fen\u00f3menos clim\u00e1ticos extremos, y la escasez de agua. Por otro lado, se suman los problemas de \u00edndole energ\u00e9tico, como son: el alto costo de la energ\u00eda, acceso limitado al suministro el\u00e9ctrico, problemas de eficiencia energ\u00e9tica y la alta dependencia de combustibles f\u00f3siles, los que se utilizan mayoritariamente en operaci\u00f3n de maquinaria agr\u00edcola, transporte e irrigaci\u00f3n.\r\n\r\nDado este contexto, esta propuesta abordar\u00e1 aspectos de \u00edndole energ\u00e9tico que suelen ser barreras para el crecimiento, la innovaci\u00f3n, y una mayor sustentabilidad en la agricultura. En este sentido, hoy en d\u00eda las micro-redes se plantean como una soluci\u00f3n real para problemas de generaci\u00f3n el\u00e9ctrica en lugares aislados de la red de suministro el\u00e9ctrico, como ocurre en muchas comunidades rurales. Al mismo tiempo, las micro-redes pueden ser una buena alternativa de autogeneraci\u00f3n complementaria que disminuya la dependencia de un servicio el\u00e9ctrico centralizado de alto costo y con problemas de interrupciones de lenta reposici\u00f3n. Esto \u00faltimo suele ser un problema frecuente en las localidades rurales.\r\n\r\nEn particular, el proyecto instalar\u00e1 y desarrollar\u00e1 en la regi\u00f3n de O\u0092Higgins capacidades humanas avanzadas y fortalecer\u00e1 la cooperaci\u00f3n internacional en tem\u00e1ticas relacionadas con el uso de micro-redes en agricultura. Tambi\u00e9n, se instalar\u00e1 un proyecto piloto de micro-red el\u00e9ctrica aplicado en cultivos bajo invernadero.\r\n\r\nDurante el desarrollo del proyecto se capacitar\u00e1n estudiantes de pregrado, postgrado, ingenieros en temas de dise\u00f1o y control de micro-redes y los desaf\u00edos que plantea su uso en el contexto de la agricultura. Una vez hecho esto, se pretende difundir el conocimiento adquirido hacia la comunidad en general, con foco en agricultores, industria agr\u00edcola y comunidad cient\u00edfica-profesional (tanto nacional como extranjera). Adem\u00e1s, se buscar\u00e1 presentar las principales conclusiones de este proyecto en conferencias cient\u00edficas nacionales y\/o internacionales. Por otro lado, el proyecto piloto de micro-red el\u00e9ctrica pretende ser un sistema demostrativo de distintas tecnolog\u00edas de generaci\u00f3n el\u00e9ctrica aplicadas en agricultura, incorporando generaci\u00f3n fotovoltaica (convencional opaca, semitransparente, y bifacial), generaci\u00f3n e\u00f3lica, y un banco de bater\u00edas. Actualmente, la Universidad de O\u0092Higgins Campus Colchagua, cuenta con dos invernaderos de 100 m2 cada uno con 10 kW de paneles fotovoltaicos instalados en sus techos, iniciativa financiada por el Gobierno Regional de O\u0092Higgins a trav\u00e9s del proyecto FIC\/IDI\/30487884-0.\r\n\r\nCon las acciones propuestas se busca fortalecer la colaboraci\u00f3n internacional, empoderar a las comunidades y promover el uso de nuevas tecnolog\u00edas y fuentes de energ\u00eda renovable como motor de desarrollo e innovaci\u00f3n en la agricultura, al mismo tiempo que se reduce la generaci\u00f3n de gases de efecto invernadero, contribuyendo a lograr una agricultura energ\u00e9ticamente sustentable.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI210021<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2021 - Junio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26054\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Red de colaboraci\u00f3n internacional para el fortalecimiento del uso de la tecnolog\u00eda NIR como una herramienta de validaci\u00f3n de calidad, origen e inocuidad de productos agropecuarios\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26054\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26054\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En la regi\u00f3n de O\u0092Higgins, como consecuencia de sus caracter\u00edsticas agroclim\u00e1ticas y recursos naturales, se han desarrollado sistemas productivos agr\u00edcolas, pecuarios y frut\u00edcolas que poseen caracter\u00edsticas particulares valoradas tradicionalmente por los consumidores. No obstante, el aumento en la vulnerabilidad de los sistemas de producci\u00f3n acaecida por los efectos del cambio clim\u00e1tico en las precipitaciones y en la presencia de eventos clim\u00e1ticos extremos hacen necesaria una valoraci\u00f3n formal de estos atributos, que se traduzca en un diferencial de precios. Por otro lado, el aumento en la intensificaci\u00f3n de la agricultura ha artificializado el sistema natural, generando una mayor presi\u00f3n sobre sus atributos estructurales y\/o funcionales en la dimensi\u00f3n biof\u00edsica. Esta situaci\u00f3n ha creado sistemas m\u00e1s simples, homog\u00e9neos y especializados, donde aumenta la velocidad de los flujos, se modifican los ciclos biogeoqu\u00edmicos, y el funcionamiento del sistema se hace dependiente del aporte de cantidades crecientes de insumos, con mayor dependencia de fuentes externas y disminuci\u00f3n de su capacidad natural de regulaci\u00f3n interna. Esta incapacidad de regulaci\u00f3n interna de sistemas artificializados genera la acumulaci\u00f3n de compuestos en los productos que abandonan el sistema. Entre compuestos destacan pesticidas, herbicidas, minerales y antibi\u00f3ticos, entre otros. Finalmente, la b\u00fasqueda de un aumento en la rentabilidad de las explotaciones agropecuarias o de los intermediarios que comercializan sus productos, conlleva la realizaci\u00f3n de pr\u00e1cticas inescrupulosas que, junto con afectar la calidad de los productos, ponen en riesgo la salud de los consumidores.\r\nConsiderando lo anteriormente descrito, se requiere de un aumento de la sostenibilidad de los sistemas de producci\u00f3n agropecuarios, respaldado en una visi\u00f3n integral de la producci\u00f3n, que valore la forma de producci\u00f3n (en sus componentes social y ambiental), el lugar de procedencia, y a la vez los atributos de calidad e inocuidad que estos componentes entregan a los alimentos.\r\nEn vista de los requerimientos antes descritos, surge la necesidad de tecnolog\u00edas y protocolos que permitan validar la calidad, origen e inocuidad de los productos agropecuarios. En Chile se han realizado esfuerzos para abordar esta tem\u00e1tica, incluyendo el desarrollo de Sello de Origen y recientemente, a trav\u00e9s de seminarios sobre Fraude alimentario y del proyecto de generaci\u00f3n de un Sistema Nacional de Referencia para la Autenticidad de los Alimentos y la trazabilidad del origen, liderados por ACHIPIA.\r\nEntre las tecnolog\u00edas utilizadas para el control de calidad de alimentos, destaca por sus caracter\u00edsticas de rapidez, inocuidad, flexibilidad y potencialidad, la tecnolog\u00eda NIR (Near Infrared Reflectance). As\u00ed, dentro de la literatura t\u00e9cnica y cient\u00edfica, es posible encontrar aplicaciones para un amplio abanico de productos, entre los que se incluyen carne, l\u00e1cteos, miel, hortalizas y frutas, en un set de aplicaciones que incluyen aspectos de calidad, patrones de alimentaci\u00f3n animal, detecci\u00f3n de pesticidas y detecci\u00f3n de antibi\u00f3ticos, por mencionar algunas.\r\nTeniendo presente la anterior, y considerando que el primer paso para la generaci\u00f3n de mecanismos de autenticidad de productos agropecuarios es la capacitaci\u00f3n de capital humano, la propuesta tiene como objetivo principal fortalecer la colaboraci\u00f3n internacional para la implementaci\u00f3n del uso de la tecnolog\u00eda NIR como una herramienta de validaci\u00f3n de calidad, origen e inocuidad de productos agropecuarios en la regi\u00f3n de O\u0092Higgins a trav\u00e9s de la capacitaci\u00f3n y difusi\u00f3n de las potenciales \u00e1reas de aplicaci\u00f3n, y a trav\u00e9s de la aplicaci\u00f3n de tecnolog\u00eda en tres productos ejemplos: miel, carne de cordero y lechugas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FOVI210021<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2021 - Junio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26311\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Red de colaboraci\u00f3n internacional para el fortalecimiento del uso de la tecnolog\u00eda NIR como una herramienta de validaci\u00f3n de calidad, origen e inocuidad de productos agropecuarios\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26311\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26311\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En la regi\u00f3n de O\u0092Higgins, como consecuencia de sus caracter\u00edsticas agroclim\u00e1ticas y recursos naturales, se han desarrollado sistemas productivos agr\u00edcolas, pecuarios y frut\u00edcolas que poseen caracter\u00edsticas particulares valoradas tradicionalmente por los consumidores. No obstante, el aumento en la vulnerabilidad de los sistemas de producci\u00f3n acaecida por los efectos del cambio clim\u00e1tico en las precipitaciones y en la presencia de eventos clim\u00e1ticos extremos hacen necesaria una valoraci\u00f3n formal de estos atributos, que se traduzca en un diferencial de precios. Por otro lado, el aumento en la intensificaci\u00f3n de la agricultura ha artificializado el sistema natural, generando una mayor presi\u00f3n sobre sus atributos estructurales y\/o funcionales en la dimensi\u00f3n biof\u00edsica. Esta situaci\u00f3n ha creado sistemas m\u00e1s simples, homog\u00e9neos y especializados, donde aumenta la velocidad de los flujos, se modifican los ciclos biogeoqu\u00edmicos, y el funcionamiento del sistema se hace dependiente del aporte de cantidades crecientes de insumos, con mayor dependencia de fuentes externas y disminuci\u00f3n de su capacidad natural de regulaci\u00f3n interna. Esta incapacidad de regulaci\u00f3n interna de sistemas artificializados genera la acumulaci\u00f3n de compuestos en los productos que abandonan el sistema. Entre compuestos destacan pesticidas, herbicidas, minerales y antibi\u00f3ticos, entre otros. Finalmente, la b\u00fasqueda de un aumento en la rentabilidad de las explotaciones agropecuarias o de los intermediarios que comercializan sus productos, conlleva la realizaci\u00f3n de pr\u00e1cticas inescrupulosas que, junto con afectar la calidad de los productos, ponen en riesgo la salud de los consumidores.\r\nConsiderando lo anteriormente descrito, se requiere de un aumento de la sostenibilidad de los sistemas de producci\u00f3n agropecuarios, respaldado en una visi\u00f3n integral de la producci\u00f3n, que valore la forma de producci\u00f3n (en sus componentes social y ambiental), el lugar de procedencia, y a la vez los atributos de calidad e inocuidad que estos componentes entregan a los alimentos.\r\nEn vista de los requerimientos antes descritos, surge la necesidad de tecnolog\u00edas y protocolos que permitan validar la calidad, origen e inocuidad de los productos agropecuarios. En Chile se han realizado esfuerzos para abordar esta tem\u00e1tica, incluyendo el desarrollo de Sello de Origen y recientemente, a trav\u00e9s de seminarios sobre Fraude alimentario y del proyecto de generaci\u00f3n de un Sistema Nacional de Referencia para la Autenticidad de los Alimentos y la trazabilidad del origen, liderados por ACHIPIA.\r\nEntre las tecnolog\u00edas utilizadas para el control de calidad de alimentos, destaca por sus caracter\u00edsticas de rapidez, inocuidad, flexibilidad y potencialidad, la tecnolog\u00eda NIR (Near Infrared Reflectance). As\u00ed, dentro de la literatura t\u00e9cnica y cient\u00edfica, es posible encontrar aplicaciones para un amplio abanico de productos, entre los que se incluyen carne, l\u00e1cteos, miel, hortalizas y frutas, en un set de aplicaciones que incluyen aspectos de calidad, patrones de alimentaci\u00f3n animal, detecci\u00f3n de pesticidas y detecci\u00f3n de antibi\u00f3ticos, por mencionar algunas.\r\nTeniendo presente la anterior, y considerando que el primer paso para la generaci\u00f3n de mecanismos de autenticidad de productos agropecuarios es la capacitaci\u00f3n de capital humano, la propuesta tiene como objetivo principal fortalecer la colaboraci\u00f3n internacional para la implementaci\u00f3n del uso de la tecnolog\u00eda NIR como una herramienta de validaci\u00f3n de calidad, origen e inocuidad de productos agropecuarios en la regi\u00f3n de O\u0092Higgins a trav\u00e9s de la capacitaci\u00f3n y difusi\u00f3n de las potenciales \u00e1reas de aplicaci\u00f3n, y a trav\u00e9s de la aplicaci\u00f3n de tecnolog\u00eda en tres productos ejemplos: miel, carne de cordero y lechugas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> NCS2021_14<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2021 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26194\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            N\u00facleo Milenio para el Estudio del Desarrollo de las Habilidades Matem\u00e1ticas Tempranas (MEMAT)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26194\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26194\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El N\u00facleo Milenio para el Estudio del Desarrollo de las Habilidades Matem\u00e1ticas Tempranas (MEMAT) busca comprender el desarrollo matem\u00e1tico temprano y promover el aprendizaje matem\u00e1tico para todos los ni\u00f1os y ni\u00f1as.\r\nBuscamos comprender c\u00f3mo las experiencias matem\u00e1ticas de los ni\u00f1os y ni\u00f1as -en m\u00faltiples contextos- contribuyen a oportunidades equitativas de aprendizaje, y entender los mecanismos que aseguran trayectorias matem\u00e1ticas exitosas en el futuro, con foco en las brechas de g\u00e9nero y NSE.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2021 - Noviembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25990\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Creacion de imagenes de super-resolucion ultrasonicas en placentas humanas ex vivo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25990\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25990\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El desarrollo de herramientas para el an &#769;alisis de funciones vitales a trav &#769;es de im &#769;agenes representa un campo de creciente inter &#769;es, especialmente para el estudio de marcadores tempranos de diversas patolog &#769;&#305;as, as &#769;&#305; como el desarrollo de aplicaciones diagn &#769;osticas a mediano plazo. En este contexto, el an &#769;alisis de la funci &#769;on vascular, a lo largo del ciclo vital, continua siendo un  &#769;area con un alta demanda de nuevas tecnolog &#769;&#305;as, debido a su gran impacto a nivel de salud en la poblaci &#769;on. Esta propuesta busca generar una l &#769;&#305;nea de investigaci &#769;on actualmente casi inexistente en Chile, las im &#769;agenes ultras &#769;onicas m &#769;edicas. En particular, nos gustar &#769;&#305;a introducir en Chile una t &#769;ecnica recientemente propuesta, denominada microscop &#769;&#305;a de localizaci &#769;on por ultrasonido (ULM), tambi &#769;en conocida como im &#769;agenes de su &#769;per- resoluci &#769;on. Esta t &#769;ecnica puede crear im &#769;agenes del sistema circulatoria con una resoluci &#769;on nunca antes vista, lo que permite visualizar vasos sangu &#769;&#305;neos de hasta 5&#956;m. As &#769;&#305;, nuestra propuesta posee dos grandes objetivos. El primero es Optimizar y robusteces los procesos involucrados en el desarrollo de las im &#769;agenes de su &#769;per-resoluci &#769;on ultras &#769;onicas, esto a trav &#769;es de Optimizar los par &#769;ametros de adquisici &#769;on de datos y de procesamiento con el fin de robustecer la generaci &#769;on de este tipo de im &#769;agenes. Nuestro segundo objetivo es generar im &#769;agenes de su &#769;per- resoluci &#769;on de la red vascular interna de placenta humana ex-vivo y a buscar candidatos a marcadores a partir de estas im &#769;agenes.\r\nLa ecograf &#769;&#305;a convencional es ampliamente usada en Chile y el mundo. Es preferida entre otras modalidades de im &#769;agenes (MRI, PET, TC) debido a su portabilidad, bajo costo, naturaleza no invasiva y a que utiliza radiaci &#769;on no ionizante, especialmente en condiciones como el embarazo, o en pacientes con manejo farmacol &#769;ogico complejo, entre otras. Recientemente, se han desarrollado nuevas modalidades de im &#769;agenes ultras &#769;onicas, propiciadas por la mejora en la industria de los semiconductores, lo que ha permitido un incremento en la capacidad de computo de los esc &#769;aneres ultraso &#769;nicos y en el nu &#769;mero de elementos piezoel &#769;ectrico de los transductores ultras &#769;onicos, generando un aumento significativo en la versatilidad y calidad de estas tecnolog &#769;&#305;as. Dentro de estas nuevas t &#769;ecnicas encontramos la microscop &#769;&#305;a de localizaci &#769;on por ultrasonido (ULM) o su &#769;per-resoluci &#769;on ultras &#769;onica. Esta revolucionaria t &#769;ecnica es capaz de superar el l &#769;&#305;mite de difracci &#769;on y producir una resoluci &#769;on diez veces mayor en comparaci &#769;on con la ecograf &#769;&#305;a convencional. Puede ser usada para producir ima &#769;genes vasculares con una resoluci &#769;on sin precedentes de hasta 5 &#956;m permitiendo as &#769;&#305; la visualizaci &#769;on de vasos sangu &#769;&#305;neos microsc &#769;opicos que hasta ahora no pueden ser vistos por ninguna t &#769;ecnica disponible cl &#769;&#305;nicamente. ULM utiliza microburbujas (MBs) de gas (1 &#956;m de di &#769;ametro) que actu &#769;an como fuentes acu &#769;sticas estoc &#769;asticas. Las MBs se inyectan en el torrente sangu &#769;&#305;neo y fluyen dentro del sistema circulatorio, donde aparecen y desaparecen de la regi &#769;on de inter &#769;es, lo que permite su localizaci &#769;on. Luego, la imagen de su &#769;per-resoluci &#769;on se construye a partir de la acumulaci &#769;on de cientos de miles de MBs localizadas.\r\nActualmente, la mayor parte de la investigaci &#769;on en ULM se realiza desde el punto de vista de las ciencias de la ingenier &#769;&#305;a, que deja a veces a la ciencia fundamental como un aspecto secundario. Nuestro equipo, debido al car &#769;acter transdisciplinario de esta propuesta, esta constituido por investigadores de el  &#769;area de la ingenier &#769;&#305;a, f &#769;&#305;sica, biomedicina y matem &#769;aticas. Basados en las fortalezas de este equipo, proponemos estudiar esta tecnolog &#769;&#305;a desde la perspectiva de la ciencia fundamental, buscando limitaciones en ella, y estableciendo los mecanismos fisiol &#769;ogicos que se manifiestan a nivel de las im &#769;agenes de su &#769;per-resoluci &#769;on, permitiendo superar sus actuales limitaciones y potenciando su posible aplicaci &#769;on en el  &#769;area m &#769;edica. En este contexto buscaremos como segundo objetivo el visualizar la microvasculatura de muestras de placenta ex-vivo, las que ser &#769;an donadas voluntariamente por pacientes del hospital regional de Rancagua, y complementar estas observaciones con par &#769;ametros funcionales y moleculares, con el fin de modelar desde distintas perspectivas nuevos marcadores de funci &#769;on vascular.\r\nUsualmente para lograr el avance en le desarrollo de este tipo de t &#769;ecnicas, se requieren condiciones experimentales altamente controlables, las que se logran utilizando sistemas que imitan el tejido en cuesti &#769;on, el que en nuestro caso es el sistema vascular. Para esto, se utilizan mayormente experimentos in-vitro fabricados a partir de microtubos de 50&#8722;150 &#956;m de di &#769;ametro interno. Sin embargo, existe una gran diferencia entre las propiedades de este tipo de sistemas y las propiedades acu &#769;sticas de tejido in-vivo humano. Lo que requiere una gran cantidad de iteraciones experimentales retazando el desarrollo. As &#769;&#305;, al utilizar tejido humano ex-vivo pretendemos aumentar significativamente la velocidad de la curva de aprendizaje y por consiguiente lograr im &#769;agenes de su &#769;per-resoluci &#769;on humano compatibles dentro de la duraci &#769;on de esta propuesta. As &#769;&#305; mismo, el desarrollo de esta propuesta en un modelo vascular como la placenta humana representa un clara oportunidad para aportar en un  &#769;area actualmente limitada en su capacidad diagn &#769;ostica, lo que restringe la aplicaci &#769;on de intervenciones efectivas durante el embarazo, con consecuencias en la salud de la madre y su progenie.\r\nComo proyecciones de este esquema colaborativo esperamos tener acceso a par &#769;ametros biol &#769;ogicos con los cuales generar nuevas formas de diagn &#769;ostico de alta precisi &#769;on, en especial a nivel de las estructuras involucradas, en primera instancia, con el desarrollo de alteraciones vasculares (i.e. vasos de pequen &#771;o calibre). Con ello buscamos desarrollar un tecnolog &#769;&#305;a con base cient &#769;&#305;fica a trav &#769;es de la cual ser &#769;a posible obtener indicadores de mayor sensibilidad y especificidad para variadas condiciones, enfermedades o s &#769;&#305;ndromes, relacionados con la funci &#769;on vascular.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2021 - Diciembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Ciencia, Tecnolog\u00eda, Conocimiento e Innovaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25992\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Divas de la Ciencia\u0094 Mujeres del Pasado Inspirando al Futuro\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25992\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25992\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Cuando pensamos en cient\u00edficos y su aporte a la ciencia, generalmente reconocemos un estereotipo masculino, acompa\u00f1ado de un desconocimiento del rol de la mujer en la ciencia. En nuestro pa\u00eds el n\u00famero de cient\u00edficos va en aumento, en n\u00famero de cient\u00edficas es de aproximadamente un 30% en las diferentes regiones del pa\u00eds. Conjuntamente,  la ciencia es reconocida como un proceso centralizado y debido a la baja difusi\u00f3n y divulgaci\u00f3n, el reconocimiento de referentes nacionales es reducido. La promoci\u00f3n del conocimiento a trav\u00e9s de sus actores en estudiantes de colegio puede incentivar la vocaci\u00f3n cient\u00edfica y promover la equidad de g\u00e9nero en \u00e1reas masculinizadas. El objetivo general de esta propuesta es: Promover el reconocimiento de Grandes Cient\u00edficas hist\u00f3ricas y de Cient\u00edfico(a)s Regionales a trav\u00e9s de la serie \u0093Divas de la Ciencia\u0094 dirigido tanto a estudiantes de colegios como al p\u00fablico general. Los objetivos espec\u00edficos son: 1) Visibilizar a Grandes Cient\u00edficas con el fin de promover su reconocimiento por el p\u00fablico general, 2) Promocionar a Cient\u00edfico(a)s Regionales como nuevos referentes cient\u00edficos por el p\u00fablico general, y 3) Integrar la serie como herramienta de ense\u00f1anza\/aprendizaje a las clases de ciencia en colegios del pa\u00eds. La serie constar\u00e1 de 12 episodios, y cada entrega tendr\u00e1 una presentaci\u00f3n animada de una \u0093Diva\u0094 (3 min) enlazada a la investigaci\u00f3n del Cient\u00edfico(a) Regional (5 min), y divulgada en un canal de YouTube. El dise\u00f1o de los episodios espera generar una experiencia memorable al exponer los problemas que debi\u00f3 enfrentar cada \u0093Diva\u0094 para lograr su investigaci\u00f3n en conjunto con la identificaci\u00f3n con el\/la Cient\u00edfico\/a Regional; adem\u00e1s de utilizar un lenguaje cercano y sencillo, musicalizaci\u00f3n y movimientos de las animaciones digitales. Los cap\u00edtulos estar\u00e1n divididos en tres ciclos de acuerdo a los programas del Mineduc: 7\u00ba-8\u00ba b\u00e1sico (ciclo I), 1\u00ba-2\u00ba Medio (ciclo II), y 3\u00ba-4\u00ba medio (ciclo III). Adem\u00e1s, los profesores interesados ser\u00e1n capacitados para utilizar la serie en sus clases a trav\u00e9s de una gu\u00eda de actividades pr\u00e1cticas. Toda la propuesta no tendr\u00e1 costo alguno para los participantes.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2021 - Mayo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26062\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Regional and Urban Landscapes: New Imagery of National Identity in Chilean Children\u0092s Literature (2010-2020)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26062\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26062\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2021 - Noviembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26113\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Creacion de imagenes de super-resolucion ultrasonicas en placentas humanas ex vivo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26113\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26113\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El desarrollo de herramientas para el an &#769;alisis de funciones vitales a trav &#769;es de im &#769;agenes representa un campo de creciente inter &#769;es, especialmente para el estudio de marcadores tempranos de diversas patolog &#769;&#305;as, as &#769;&#305; como el desarrollo de aplicaciones diagn &#769;osticas a mediano plazo. En este contexto, el an &#769;alisis de la funci &#769;on vascular, a lo largo del ciclo vital, continua siendo un  &#769;area con un alta demanda de nuevas tecnolog &#769;&#305;as, debido a su gran impacto a nivel de salud en la poblaci &#769;on. Esta propuesta busca generar una l &#769;&#305;nea de investigaci &#769;on actualmente casi inexistente en Chile, las im &#769;agenes ultras &#769;onicas m &#769;edicas. En particular, nos gustar &#769;&#305;a introducir en Chile una t &#769;ecnica recientemente propuesta, denominada microscop &#769;&#305;a de localizaci &#769;on por ultrasonido (ULM), tambi &#769;en conocida como im &#769;agenes de su &#769;per- resoluci &#769;on. Esta t &#769;ecnica puede crear im &#769;agenes del sistema circulatoria con una resoluci &#769;on nunca antes vista, lo que permite visualizar vasos sangu &#769;&#305;neos de hasta 5&#956;m. As &#769;&#305;, nuestra propuesta posee dos grandes objetivos. El primero es Optimizar y robusteces los procesos involucrados en el desarrollo de las im &#769;agenes de su &#769;per-resoluci &#769;on ultras &#769;onicas, esto a trav &#769;es de Optimizar los par &#769;ametros de adquisici &#769;on de datos y de procesamiento con el fin de robustecer la generaci &#769;on de este tipo de im &#769;agenes. Nuestro segundo objetivo es generar im &#769;agenes de su &#769;per- resoluci &#769;on de la red vascular interna de placenta humana ex-vivo y a buscar candidatos a marcadores a partir de estas im &#769;agenes.\r\nLa ecograf &#769;&#305;a convencional es ampliamente usada en Chile y el mundo. Es preferida entre otras modalidades de im &#769;agenes (MRI, PET, TC) debido a su portabilidad, bajo costo, naturaleza no invasiva y a que utiliza radiaci &#769;on no ionizante, especialmente en condiciones como el embarazo, o en pacientes con manejo farmacol &#769;ogico complejo, entre otras. Recientemente, se han desarrollado nuevas modalidades de im &#769;agenes ultras &#769;onicas, propiciadas por la mejora en la industria de los semiconductores, lo que ha permitido un incremento en la capacidad de computo de los esc &#769;aneres ultraso &#769;nicos y en el nu &#769;mero de elementos piezoel &#769;ectrico de los transductores ultras &#769;onicos, generando un aumento significativo en la versatilidad y calidad de estas tecnolog &#769;&#305;as. Dentro de estas nuevas t &#769;ecnicas encontramos la microscop &#769;&#305;a de localizaci &#769;on por ultrasonido (ULM) o su &#769;per-resoluci &#769;on ultras &#769;onica. Esta revolucionaria t &#769;ecnica es capaz de superar el l &#769;&#305;mite de difracci &#769;on y producir una resoluci &#769;on diez veces mayor en comparaci &#769;on con la ecograf &#769;&#305;a convencional. Puede ser usada para producir ima &#769;genes vasculares con una resoluci &#769;on sin precedentes de hasta 5 &#956;m permitiendo as &#769;&#305; la visualizaci &#769;on de vasos sangu &#769;&#305;neos microsc &#769;opicos que hasta ahora no pueden ser vistos por ninguna t &#769;ecnica disponible cl &#769;&#305;nicamente. ULM utiliza microburbujas (MBs) de gas (1 &#956;m de di &#769;ametro) que actu &#769;an como fuentes acu &#769;sticas estoc &#769;asticas. Las MBs se inyectan en el torrente sangu &#769;&#305;neo y fluyen dentro del sistema circulatorio, donde aparecen y desaparecen de la regi &#769;on de inter &#769;es, lo que permite su localizaci &#769;on. Luego, la imagen de su &#769;per-resoluci &#769;on se construye a partir de la acumulaci &#769;on de cientos de miles de MBs localizadas.\r\nActualmente, la mayor parte de la investigaci &#769;on en ULM se realiza desde el punto de vista de las ciencias de la ingenier &#769;&#305;a, que deja a veces a la ciencia fundamental como un aspecto secundario. Nuestro equipo, debido al car &#769;acter transdisciplinario de esta propuesta, esta constituido por investigadores de el  &#769;area de la ingenier &#769;&#305;a, f &#769;&#305;sica, biomedicina y matem &#769;aticas. Basados en las fortalezas de este equipo, proponemos estudiar esta tecnolog &#769;&#305;a desde la perspectiva de la ciencia fundamental, buscando limitaciones en ella, y estableciendo los mecanismos fisiol &#769;ogicos que se manifiestan a nivel de las im &#769;agenes de su &#769;per-resoluci &#769;on, permitiendo superar sus actuales limitaciones y potenciando su posible aplicaci &#769;on en el  &#769;area m &#769;edica. En este contexto buscaremos como segundo objetivo el visualizar la microvasculatura de muestras de placenta ex-vivo, las que ser &#769;an donadas voluntariamente por pacientes del hospital regional de Rancagua, y complementar estas observaciones con par &#769;ametros funcionales y moleculares, con el fin de modelar desde distintas perspectivas nuevos marcadores de funci &#769;on vascular.\r\nUsualmente para lograr el avance en le desarrollo de este tipo de t &#769;ecnicas, se requieren condiciones experimentales altamente controlables, las que se logran utilizando sistemas que imitan el tejido en cuesti &#769;on, el que en nuestro caso es el sistema vascular. Para esto, se utilizan mayormente experimentos in-vitro fabricados a partir de microtubos de 50&#8722;150 &#956;m de di &#769;ametro interno. Sin embargo, existe una gran diferencia entre las propiedades de este tipo de sistemas y las propiedades acu &#769;sticas de tejido in-vivo humano. Lo que requiere una gran cantidad de iteraciones experimentales retazando el desarrollo. As &#769;&#305;, al utilizar tejido humano ex-vivo pretendemos aumentar significativamente la velocidad de la curva de aprendizaje y por consiguiente lograr im &#769;agenes de su &#769;per-resoluci &#769;on humano compatibles dentro de la duraci &#769;on de esta propuesta. As &#769;&#305; mismo, el desarrollo de esta propuesta en un modelo vascular como la placenta humana representa un clara oportunidad para aportar en un  &#769;area actualmente limitada en su capacidad diagn &#769;ostica, lo que restringe la aplicaci &#769;on de intervenciones efectivas durante el embarazo, con consecuencias en la salud de la madre y su progenie.\r\nComo proyecciones de este esquema colaborativo esperamos tener acceso a par &#769;ametros biol &#769;ogicos con los cuales generar nuevas formas de diagn &#769;ostico de alta precisi &#769;on, en especial a nivel de las estructuras involucradas, en primera instancia, con el desarrollo de alteraciones vasculares (i.e. vasos de pequen &#771;o calibre). Con ello buscamos desarrollar un tecnolog &#769;&#305;a con base cient &#769;&#305;fica a trav &#769;es de la cual ser &#769;a posible obtener indicadores de mayor sensibilidad y especificidad para variadas condiciones, enfermedades o s &#769;&#305;ndromes, relacionados con la funci &#769;on vascular.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2021 - Noviembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26245\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Systems Biology Center for the study of extremophile communities from mining tailings. Anillo ACT210004.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26245\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26245\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Con la apertura de la mina\r\n\r\nEl Teniente\r\n\r\nen 1905, Chile\r\npromovi\u00f3 la explotaci\u00f3n a gran escala del cobre llamado \"Gran\r\nMiner\u00eda del Cobre\". De ese momento a la fecha, se registran un\r\ntotal de 757 relaves minero, dentro de los cuales un 85% de ellos\r\nest\u00e1n abandonados o inactivos. Estos n\u00fameros posicionan a los\r\nrelaves como un problema importante, siendo actualmente el\r\npasivo ambiental de mayor impacto en nuestro pa\u00eds. En\r\nparticular, el relave Cauquenes ubicado en la Regi\u00f3n de\r\nO\r\nHiggins, es el relave de cobre m\u00e1s antiguo y de mayor\r\ndimensi\u00f3n, reservorio a la fecha del material depositado por El\r\nTeniente. Considerando el n\u00famero, tama\u00f1o y dimensiones,\r\nsumado a la complejidad del escenario ambiental y las variables\r\ninvolucradas, el estudio de las comunidades microbianas que\r\nhabitan los relaves mineros debe abordarse desde diferentes\r\ndisciplinas. Por estos motivos, a trav\u00e9s de la interconexi\u00f3n de las\r\ndiversas capacidades de investigadores nacionales e\r\ninternacionales, el presente proyecto busca sentar las bases para\r\nla creaci\u00f3n de un Centro de Biolog\u00eda de Sistemas para el estudio\r\nde comunidades que habitan relaves mineros. A nivel de\r\ninvestigaci\u00f3n. el Centro se enfocar\u00e1 en: i) Caracterizar la\r\nestructura de las comunidades extrem\u00f3filas de los relaves. ii)\r\nIdentificar y validar de los potenciales metab\u00f3licos de las\r\ncomunidades y sus miembros. iii) Generar un registro y\r\nclasificaci\u00f3n de informaci\u00f3n - Bases de datos y colecci\u00f3n de\r\ncepas. iv) Desarrollo de biotecnolog\u00eda para aplicaciones en\r\nminer\u00eda. En definitiva, con un fuerte compromiso regional, el\r\nproyecto contempla abordar por primera vez desde una\r\nperspectiva multidisciplinaria e integral, el estudio de\r\ncomunidades de especies extrem\u00f3filas presentes en el relave\r\nCauquenes, sentando las bases para que el Centro de Biolog\u00eda de\r\nSistemas pueda en el corto plazo, proyectarse como un espacio\r\nreal para al estudio de microorganismos que habitan los relaves\r\nen Chile.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2021 - Noviembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26386\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Systems Biology Center for the study of extremophile communities from mining tailings. Anillo ACT210004.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26386\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26386\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Con la apertura de la mina\r\n\r\nEl Teniente\r\n\r\nen 1905, Chile\r\npromovi\u00f3 la explotaci\u00f3n a gran escala del cobre llamado \"Gran\r\nMiner\u00eda del Cobre\". De ese momento a la fecha, se registran un\r\ntotal de 757 relaves minero, dentro de los cuales un 85% de ellos\r\nest\u00e1n abandonados o inactivos. Estos n\u00fameros posicionan a los\r\nrelaves como un problema importante, siendo actualmente el\r\npasivo ambiental de mayor impacto en nuestro pa\u00eds. En\r\nparticular, el relave Cauquenes ubicado en la Regi\u00f3n de\r\nO\r\nHiggins, es el relave de cobre m\u00e1s antiguo y de mayor\r\ndimensi\u00f3n, reservorio a la fecha del material depositado por El\r\nTeniente. Considerando el n\u00famero, tama\u00f1o y dimensiones,\r\nsumado a la complejidad del escenario ambiental y las variables\r\ninvolucradas, el estudio de las comunidades microbianas que\r\nhabitan los relaves mineros debe abordarse desde diferentes\r\ndisciplinas. Por estos motivos, a trav\u00e9s de la interconexi\u00f3n de las\r\ndiversas capacidades de investigadores nacionales e\r\ninternacionales, el presente proyecto busca sentar las bases para\r\nla creaci\u00f3n de un Centro de Biolog\u00eda de Sistemas para el estudio\r\nde comunidades que habitan relaves mineros. A nivel de\r\ninvestigaci\u00f3n. el Centro se enfocar\u00e1 en: i) Caracterizar la\r\nestructura de las comunidades extrem\u00f3filas de los relaves. ii)\r\nIdentificar y validar de los potenciales metab\u00f3licos de las\r\ncomunidades y sus miembros. iii) Generar un registro y\r\nclasificaci\u00f3n de informaci\u00f3n - Bases de datos y colecci\u00f3n de\r\ncepas. iv) Desarrollo de biotecnolog\u00eda para aplicaciones en\r\nminer\u00eda. En definitiva, con un fuerte compromiso regional, el\r\nproyecto contempla abordar por primera vez desde una\r\nperspectiva multidisciplinaria e integral, el estudio de\r\ncomunidades de especies extrem\u00f3filas presentes en el relave\r\nCauquenes, sentando las bases para que el Centro de Biolog\u00eda de\r\nSistemas pueda en el corto plazo, proyectarse como un espacio\r\nreal para al estudio de microorganismos que habitan los relaves\r\nen Chile.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2021 - Noviembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26518\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Creacion de imagenes de super-resolucion ultrasonicas en placentas humanas ex vivo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26518\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26518\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El desarrollo de herramientas para el an &#769;alisis de funciones vitales a trav &#769;es de im &#769;agenes representa un campo de creciente inter &#769;es, especialmente para el estudio de marcadores tempranos de diversas patolog &#769;&#305;as, as &#769;&#305; como el desarrollo de aplicaciones diagn &#769;osticas a mediano plazo. En este contexto, el an &#769;alisis de la funci &#769;on vascular, a lo largo del ciclo vital, continua siendo un  &#769;area con un alta demanda de nuevas tecnolog &#769;&#305;as, debido a su gran impacto a nivel de salud en la poblaci &#769;on. Esta propuesta busca generar una l &#769;&#305;nea de investigaci &#769;on actualmente casi inexistente en Chile, las im &#769;agenes ultras &#769;onicas m &#769;edicas. En particular, nos gustar &#769;&#305;a introducir en Chile una t &#769;ecnica recientemente propuesta, denominada microscop &#769;&#305;a de localizaci &#769;on por ultrasonido (ULM), tambi &#769;en conocida como im &#769;agenes de su &#769;per- resoluci &#769;on. Esta t &#769;ecnica puede crear im &#769;agenes del sistema circulatoria con una resoluci &#769;on nunca antes vista, lo que permite visualizar vasos sangu &#769;&#305;neos de hasta 5&#956;m. As &#769;&#305;, nuestra propuesta posee dos grandes objetivos. El primero es Optimizar y robusteces los procesos involucrados en el desarrollo de las im &#769;agenes de su &#769;per-resoluci &#769;on ultras &#769;onicas, esto a trav &#769;es de Optimizar los par &#769;ametros de adquisici &#769;on de datos y de procesamiento con el fin de robustecer la generaci &#769;on de este tipo de im &#769;agenes. Nuestro segundo objetivo es generar im &#769;agenes de su &#769;per- resoluci &#769;on de la red vascular interna de placenta humana ex-vivo y a buscar candidatos a marcadores a partir de estas im &#769;agenes.\r\nLa ecograf &#769;&#305;a convencional es ampliamente usada en Chile y el mundo. Es preferida entre otras modalidades de im &#769;agenes (MRI, PET, TC) debido a su portabilidad, bajo costo, naturaleza no invasiva y a que utiliza radiaci &#769;on no ionizante, especialmente en condiciones como el embarazo, o en pacientes con manejo farmacol &#769;ogico complejo, entre otras. Recientemente, se han desarrollado nuevas modalidades de im &#769;agenes ultras &#769;onicas, propiciadas por la mejora en la industria de los semiconductores, lo que ha permitido un incremento en la capacidad de computo de los esc &#769;aneres ultraso &#769;nicos y en el nu &#769;mero de elementos piezoel &#769;ectrico de los transductores ultras &#769;onicos, generando un aumento significativo en la versatilidad y calidad de estas tecnolog &#769;&#305;as. Dentro de estas nuevas t &#769;ecnicas encontramos la microscop &#769;&#305;a de localizaci &#769;on por ultrasonido (ULM) o su &#769;per-resoluci &#769;on ultras &#769;onica. Esta revolucionaria t &#769;ecnica es capaz de superar el l &#769;&#305;mite de difracci &#769;on y producir una resoluci &#769;on diez veces mayor en comparaci &#769;on con la ecograf &#769;&#305;a convencional. Puede ser usada para producir ima &#769;genes vasculares con una resoluci &#769;on sin precedentes de hasta 5 &#956;m permitiendo as &#769;&#305; la visualizaci &#769;on de vasos sangu &#769;&#305;neos microsc &#769;opicos que hasta ahora no pueden ser vistos por ninguna t &#769;ecnica disponible cl &#769;&#305;nicamente. ULM utiliza microburbujas (MBs) de gas (1 &#956;m de di &#769;ametro) que actu &#769;an como fuentes acu &#769;sticas estoc &#769;asticas. Las MBs se inyectan en el torrente sangu &#769;&#305;neo y fluyen dentro del sistema circulatorio, donde aparecen y desaparecen de la regi &#769;on de inter &#769;es, lo que permite su localizaci &#769;on. Luego, la imagen de su &#769;per-resoluci &#769;on se construye a partir de la acumulaci &#769;on de cientos de miles de MBs localizadas.\r\nActualmente, la mayor parte de la investigaci &#769;on en ULM se realiza desde el punto de vista de las ciencias de la ingenier &#769;&#305;a, que deja a veces a la ciencia fundamental como un aspecto secundario. Nuestro equipo, debido al car &#769;acter transdisciplinario de esta propuesta, esta constituido por investigadores de el  &#769;area de la ingenier &#769;&#305;a, f &#769;&#305;sica, biomedicina y matem &#769;aticas. Basados en las fortalezas de este equipo, proponemos estudiar esta tecnolog &#769;&#305;a desde la perspectiva de la ciencia fundamental, buscando limitaciones en ella, y estableciendo los mecanismos fisiol &#769;ogicos que se manifiestan a nivel de las im &#769;agenes de su &#769;per-resoluci &#769;on, permitiendo superar sus actuales limitaciones y potenciando su posible aplicaci &#769;on en el  &#769;area m &#769;edica. En este contexto buscaremos como segundo objetivo el visualizar la microvasculatura de muestras de placenta ex-vivo, las que ser &#769;an donadas voluntariamente por pacientes del hospital regional de Rancagua, y complementar estas observaciones con par &#769;ametros funcionales y moleculares, con el fin de modelar desde distintas perspectivas nuevos marcadores de funci &#769;on vascular.\r\nUsualmente para lograr el avance en le desarrollo de este tipo de t &#769;ecnicas, se requieren condiciones experimentales altamente controlables, las que se logran utilizando sistemas que imitan el tejido en cuesti &#769;on, el que en nuestro caso es el sistema vascular. Para esto, se utilizan mayormente experimentos in-vitro fabricados a partir de microtubos de 50&#8722;150 &#956;m de di &#769;ametro interno. Sin embargo, existe una gran diferencia entre las propiedades de este tipo de sistemas y las propiedades acu &#769;sticas de tejido in-vivo humano. Lo que requiere una gran cantidad de iteraciones experimentales retazando el desarrollo. As &#769;&#305;, al utilizar tejido humano ex-vivo pretendemos aumentar significativamente la velocidad de la curva de aprendizaje y por consiguiente lograr im &#769;agenes de su &#769;per-resoluci &#769;on humano compatibles dentro de la duraci &#769;on de esta propuesta. As &#769;&#305; mismo, el desarrollo de esta propuesta en un modelo vascular como la placenta humana representa un clara oportunidad para aportar en un  &#769;area actualmente limitada en su capacidad diagn &#769;ostica, lo que restringe la aplicaci &#769;on de intervenciones efectivas durante el embarazo, con consecuencias en la salud de la madre y su progenie.\r\nComo proyecciones de este esquema colaborativo esperamos tener acceso a par &#769;ametros biol &#769;ogicos con los cuales generar nuevas formas de diagn &#769;ostico de alta precisi &#769;on, en especial a nivel de las estructuras involucradas, en primera instancia, con el desarrollo de alteraciones vasculares (i.e. vasos de pequen &#771;o calibre). Con ello buscamos desarrollar un tecnolog &#769;&#305;a con base cient &#769;&#305;fica a trav &#769;es de la cual ser &#769;a posible obtener indicadores de mayor sensibilidad y especificidad para variadas condiciones, enfermedades o s &#769;&#305;ndromes, relacionados con la funci &#769;on vascular.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2021 - Noviembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26519\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Systems Biology Center for the study of extremophile communities from mining tailings. Anillo ACT210004.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26519\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26519\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Con la apertura de la mina\r\n\r\nEl Teniente\r\n\r\nen 1905, Chile\r\npromovi\u00f3 la explotaci\u00f3n a gran escala del cobre llamado \"Gran\r\nMiner\u00eda del Cobre\". De ese momento a la fecha, se registran un\r\ntotal de 757 relaves minero, dentro de los cuales un 85% de ellos\r\nest\u00e1n abandonados o inactivos. Estos n\u00fameros posicionan a los\r\nrelaves como un problema importante, siendo actualmente el\r\npasivo ambiental de mayor impacto en nuestro pa\u00eds. En\r\nparticular, el relave Cauquenes ubicado en la Regi\u00f3n de\r\nO\r\nHiggins, es el relave de cobre m\u00e1s antiguo y de mayor\r\ndimensi\u00f3n, reservorio a la fecha del material depositado por El\r\nTeniente. Considerando el n\u00famero, tama\u00f1o y dimensiones,\r\nsumado a la complejidad del escenario ambiental y las variables\r\ninvolucradas, el estudio de las comunidades microbianas que\r\nhabitan los relaves mineros debe abordarse desde diferentes\r\ndisciplinas. Por estos motivos, a trav\u00e9s de la interconexi\u00f3n de las\r\ndiversas capacidades de investigadores nacionales e\r\ninternacionales, el presente proyecto busca sentar las bases para\r\nla creaci\u00f3n de un Centro de Biolog\u00eda de Sistemas para el estudio\r\nde comunidades que habitan relaves mineros. A nivel de\r\ninvestigaci\u00f3n. el Centro se enfocar\u00e1 en: i) Caracterizar la\r\nestructura de las comunidades extrem\u00f3filas de los relaves. ii)\r\nIdentificar y validar de los potenciales metab\u00f3licos de las\r\ncomunidades y sus miembros. iii) Generar un registro y\r\nclasificaci\u00f3n de informaci\u00f3n - Bases de datos y colecci\u00f3n de\r\ncepas. iv) Desarrollo de biotecnolog\u00eda para aplicaciones en\r\nminer\u00eda. En definitiva, con un fuerte compromiso regional, el\r\nproyecto contempla abordar por primera vez desde una\r\nperspectiva multidisciplinaria e integral, el estudio de\r\ncomunidades de especies extrem\u00f3filas presentes en el relave\r\nCauquenes, sentando las bases para que el Centro de Biolog\u00eda de\r\nSistemas pueda en el corto plazo, proyectarse como un espacio\r\nreal para al estudio de microorganismos que habitan los relaves\r\nen Chile.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2021 - Noviembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26610\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Creacion de imagenes de super-resolucion ultrasonicas en placentas humanas ex vivo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26610\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26610\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El desarrollo de herramientas para el an &#769;alisis de funciones vitales a trav &#769;es de im &#769;agenes representa un campo de creciente inter &#769;es, especialmente para el estudio de marcadores tempranos de diversas patolog &#769;&#305;as, as &#769;&#305; como el desarrollo de aplicaciones diagn &#769;osticas a mediano plazo. En este contexto, el an &#769;alisis de la funci &#769;on vascular, a lo largo del ciclo vital, continua siendo un  &#769;area con un alta demanda de nuevas tecnolog &#769;&#305;as, debido a su gran impacto a nivel de salud en la poblaci &#769;on. Esta propuesta busca generar una l &#769;&#305;nea de investigaci &#769;on actualmente casi inexistente en Chile, las im &#769;agenes ultras &#769;onicas m &#769;edicas. En particular, nos gustar &#769;&#305;a introducir en Chile una t &#769;ecnica recientemente propuesta, denominada microscop &#769;&#305;a de localizaci &#769;on por ultrasonido (ULM), tambi &#769;en conocida como im &#769;agenes de su &#769;per- resoluci &#769;on. Esta t &#769;ecnica puede crear im &#769;agenes del sistema circulatoria con una resoluci &#769;on nunca antes vista, lo que permite visualizar vasos sangu &#769;&#305;neos de hasta 5&#956;m. As &#769;&#305;, nuestra propuesta posee dos grandes objetivos. El primero es Optimizar y robusteces los procesos involucrados en el desarrollo de las im &#769;agenes de su &#769;per-resoluci &#769;on ultras &#769;onicas, esto a trav &#769;es de Optimizar los par &#769;ametros de adquisici &#769;on de datos y de procesamiento con el fin de robustecer la generaci &#769;on de este tipo de im &#769;agenes. Nuestro segundo objetivo es generar im &#769;agenes de su &#769;per- resoluci &#769;on de la red vascular interna de placenta humana ex-vivo y a buscar candidatos a marcadores a partir de estas im &#769;agenes.\r\nLa ecograf &#769;&#305;a convencional es ampliamente usada en Chile y el mundo. Es preferida entre otras modalidades de im &#769;agenes (MRI, PET, TC) debido a su portabilidad, bajo costo, naturaleza no invasiva y a que utiliza radiaci &#769;on no ionizante, especialmente en condiciones como el embarazo, o en pacientes con manejo farmacol &#769;ogico complejo, entre otras. Recientemente, se han desarrollado nuevas modalidades de im &#769;agenes ultras &#769;onicas, propiciadas por la mejora en la industria de los semiconductores, lo que ha permitido un incremento en la capacidad de computo de los esc &#769;aneres ultraso &#769;nicos y en el nu &#769;mero de elementos piezoel &#769;ectrico de los transductores ultras &#769;onicos, generando un aumento significativo en la versatilidad y calidad de estas tecnolog &#769;&#305;as. Dentro de estas nuevas t &#769;ecnicas encontramos la microscop &#769;&#305;a de localizaci &#769;on por ultrasonido (ULM) o su &#769;per-resoluci &#769;on ultras &#769;onica. Esta revolucionaria t &#769;ecnica es capaz de superar el l &#769;&#305;mite de difracci &#769;on y producir una resoluci &#769;on diez veces mayor en comparaci &#769;on con la ecograf &#769;&#305;a convencional. Puede ser usada para producir ima &#769;genes vasculares con una resoluci &#769;on sin precedentes de hasta 5 &#956;m permitiendo as &#769;&#305; la visualizaci &#769;on de vasos sangu &#769;&#305;neos microsc &#769;opicos que hasta ahora no pueden ser vistos por ninguna t &#769;ecnica disponible cl &#769;&#305;nicamente. ULM utiliza microburbujas (MBs) de gas (1 &#956;m de di &#769;ametro) que actu &#769;an como fuentes acu &#769;sticas estoc &#769;asticas. Las MBs se inyectan en el torrente sangu &#769;&#305;neo y fluyen dentro del sistema circulatorio, donde aparecen y desaparecen de la regi &#769;on de inter &#769;es, lo que permite su localizaci &#769;on. Luego, la imagen de su &#769;per-resoluci &#769;on se construye a partir de la acumulaci &#769;on de cientos de miles de MBs localizadas.\r\nActualmente, la mayor parte de la investigaci &#769;on en ULM se realiza desde el punto de vista de las ciencias de la ingenier &#769;&#305;a, que deja a veces a la ciencia fundamental como un aspecto secundario. Nuestro equipo, debido al car &#769;acter transdisciplinario de esta propuesta, esta constituido por investigadores de el  &#769;area de la ingenier &#769;&#305;a, f &#769;&#305;sica, biomedicina y matem &#769;aticas. Basados en las fortalezas de este equipo, proponemos estudiar esta tecnolog &#769;&#305;a desde la perspectiva de la ciencia fundamental, buscando limitaciones en ella, y estableciendo los mecanismos fisiol &#769;ogicos que se manifiestan a nivel de las im &#769;agenes de su &#769;per-resoluci &#769;on, permitiendo superar sus actuales limitaciones y potenciando su posible aplicaci &#769;on en el  &#769;area m &#769;edica. En este contexto buscaremos como segundo objetivo el visualizar la microvasculatura de muestras de placenta ex-vivo, las que ser &#769;an donadas voluntariamente por pacientes del hospital regional de Rancagua, y complementar estas observaciones con par &#769;ametros funcionales y moleculares, con el fin de modelar desde distintas perspectivas nuevos marcadores de funci &#769;on vascular.\r\nUsualmente para lograr el avance en le desarrollo de este tipo de t &#769;ecnicas, se requieren condiciones experimentales altamente controlables, las que se logran utilizando sistemas que imitan el tejido en cuesti &#769;on, el que en nuestro caso es el sistema vascular. Para esto, se utilizan mayormente experimentos in-vitro fabricados a partir de microtubos de 50&#8722;150 &#956;m de di &#769;ametro interno. Sin embargo, existe una gran diferencia entre las propiedades de este tipo de sistemas y las propiedades acu &#769;sticas de tejido in-vivo humano. Lo que requiere una gran cantidad de iteraciones experimentales retazando el desarrollo. As &#769;&#305;, al utilizar tejido humano ex-vivo pretendemos aumentar significativamente la velocidad de la curva de aprendizaje y por consiguiente lograr im &#769;agenes de su &#769;per-resoluci &#769;on humano compatibles dentro de la duraci &#769;on de esta propuesta. As &#769;&#305; mismo, el desarrollo de esta propuesta en un modelo vascular como la placenta humana representa un clara oportunidad para aportar en un  &#769;area actualmente limitada en su capacidad diagn &#769;ostica, lo que restringe la aplicaci &#769;on de intervenciones efectivas durante el embarazo, con consecuencias en la salud de la madre y su progenie.\r\nComo proyecciones de este esquema colaborativo esperamos tener acceso a par &#769;ametros biol &#769;ogicos con los cuales generar nuevas formas de diagn &#769;ostico de alta precisi &#769;on, en especial a nivel de las estructuras involucradas, en primera instancia, con el desarrollo de alteraciones vasculares (i.e. vasos de pequen &#771;o calibre). Con ello buscamos desarrollar un tecnolog &#769;&#305;a con base cient &#769;&#305;fica a trav &#769;es de la cual ser &#769;a posible obtener indicadores de mayor sensibilidad y especificidad para variadas condiciones, enfermedades o s &#769;&#305;ndromes, relacionados con la funci &#769;on vascular.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2021 - Diciembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Ciencia, Tecnolog\u00eda, Conocimiento e Innovaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26611\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Divas de la Ciencia\u0094 Mujeres del Pasado Inspirando al Futuro\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26611\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26611\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Cuando pensamos en cient\u00edficos y su aporte a la ciencia, generalmente reconocemos un estereotipo masculino, acompa\u00f1ado de un desconocimiento del rol de la mujer en la ciencia. En nuestro pa\u00eds el n\u00famero de cient\u00edficos va en aumento, en n\u00famero de cient\u00edficas es de aproximadamente un 30% en las diferentes regiones del pa\u00eds. Conjuntamente,  la ciencia es reconocida como un proceso centralizado y debido a la baja difusi\u00f3n y divulgaci\u00f3n, el reconocimiento de referentes nacionales es reducido. La promoci\u00f3n del conocimiento a trav\u00e9s de sus actores en estudiantes de colegio puede incentivar la vocaci\u00f3n cient\u00edfica y promover la equidad de g\u00e9nero en \u00e1reas masculinizadas. El objetivo general de esta propuesta es: Promover el reconocimiento de Grandes Cient\u00edficas hist\u00f3ricas y de Cient\u00edfico(a)s Regionales a trav\u00e9s de la serie \u0093Divas de la Ciencia\u0094 dirigido tanto a estudiantes de colegios como al p\u00fablico general. Los objetivos espec\u00edficos son: 1) Visibilizar a Grandes Cient\u00edficas con el fin de promover su reconocimiento por el p\u00fablico general, 2) Promocionar a Cient\u00edfico(a)s Regionales como nuevos referentes cient\u00edficos por el p\u00fablico general, y 3) Integrar la serie como herramienta de ense\u00f1anza\/aprendizaje a las clases de ciencia en colegios del pa\u00eds. La serie constar\u00e1 de 12 episodios, y cada entrega tendr\u00e1 una presentaci\u00f3n animada de una \u0093Diva\u0094 (3 min) enlazada a la investigaci\u00f3n del Cient\u00edfico(a) Regional (5 min), y divulgada en un canal de YouTube. El dise\u00f1o de los episodios espera generar una experiencia memorable al exponer los problemas que debi\u00f3 enfrentar cada \u0093Diva\u0094 para lograr su investigaci\u00f3n en conjunto con la identificaci\u00f3n con el\/la Cient\u00edfico\/a Regional; adem\u00e1s de utilizar un lenguaje cercano y sencillo, musicalizaci\u00f3n y movimientos de las animaciones digitales. Los cap\u00edtulos estar\u00e1n divididos en tres ciclos de acuerdo a los programas del Mineduc: 7\u00ba-8\u00ba b\u00e1sico (ciclo I), 1\u00ba-2\u00ba Medio (ciclo II), y 3\u00ba-4\u00ba medio (ciclo III). Adem\u00e1s, los profesores interesados ser\u00e1n capacitados para utilizar la serie en sus clases a trav\u00e9s de una gu\u00eda de actividades pr\u00e1cticas. Toda la propuesta no tendr\u00e1 costo alguno para los participantes.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2021 - Junio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26812\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desarrollo de un sistema digital de evaluaci\u00f3n, seguimiento y recomendaci\u00f3n de estrategias de participaci\u00f3n comunitaria para dispositivos y redes de salud mental\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26812\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26812\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El diagn\u00f3stico de la situaci\u00f3n de salud mental a nivel global y local mantiene resultados\r\npreocupantes, que, sumados al efecto de la pandemia por COVID-19, se traducen en mayor\r\nmagnitud, severidad e inequidad. La participaci\u00f3n comunitaria en salud (PCS) se postula\r\nfrecuentemente como una estrategia transversal que contribuye a abordar estos desaf\u00edos, sostenida\r\ntanto por lineamientos program\u00e1ticos como por la evidencia disponible. Sin embargo, los estudios\r\nsuelen concluir que los componentes espec\u00edficos de las estrategias de participaci\u00f3n son poco claros.\r\nSe sostiene que una falta de claridad conceptual y su traducci\u00f3n operacional dificulta la evaluaci\u00f3n\r\nde su efectividad y eficiencia en los resultados de salud. La presente propuesta sostiene que esta\r\nambig\u00fcedad conceptual y consecuente ausencia de m\u00e9tricas b\u00e1sicas en materia de participaci\u00f3n,\r\nobstaculiza su desarrollo como una dimensi\u00f3n integrada con los sistemas de salud. En virtud de ello,\r\nel proyecto tiene como objetivo central el Desarrollo de un Sistema de Evaluaci\u00f3n, Seguimiento y\r\nRecomendaci\u00f3n de PCS para los dispositivos de salud. Para ello se plantea la (1) Formulaci\u00f3n de un\r\nmodelo conceptual sobre la base de revisi\u00f3n exploratoria de literatura, grupos focales y con el\r\nm\u00e9todo Delphi de consenso de expertos\/as (por experiencia y disciplinares); (2) Dise\u00f1o de un\r\ninstrumento de evaluaci\u00f3n de PCS en los dispositivos de salud, validado sobre una muestra\r\nrepresentativa de centros de salud, estratificada por variables relevantes (rural\/urbano y NSE) en\r\ntres territorios de servicios de salud y 3) Desarrollo de un herramienta digital que aloje al\r\ninstrumento, con funcionalidades para reportar recomendaciones en base a algoritmos. Se espera\r\nque este sistema contribuya a fortalecer la participaci\u00f3n comunitaria en el sistema de salud, as\u00ed\r\ncomo generar m\u00e9tricas para estudios observacionales sobre factores que favorecen la PCS y la\r\nforma en la que esta contribuye a los resultados de salud poblacionales[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2021 - Noviembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26943\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Systems Biology Center for the study of extremophile communities from mining tailings. Anillo ACT210004.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26943\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26943\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Con la apertura de la mina\r\n\r\nEl Teniente\r\n\r\nen 1905, Chile\r\npromovi\u00f3 la explotaci\u00f3n a gran escala del cobre llamado \"Gran\r\nMiner\u00eda del Cobre\". De ese momento a la fecha, se registran un\r\ntotal de 757 relaves minero, dentro de los cuales un 85% de ellos\r\nest\u00e1n abandonados o inactivos. Estos n\u00fameros posicionan a los\r\nrelaves como un problema importante, siendo actualmente el\r\npasivo ambiental de mayor impacto en nuestro pa\u00eds. En\r\nparticular, el relave Cauquenes ubicado en la Regi\u00f3n de\r\nO\r\nHiggins, es el relave de cobre m\u00e1s antiguo y de mayor\r\ndimensi\u00f3n, reservorio a la fecha del material depositado por El\r\nTeniente. Considerando el n\u00famero, tama\u00f1o y dimensiones,\r\nsumado a la complejidad del escenario ambiental y las variables\r\ninvolucradas, el estudio de las comunidades microbianas que\r\nhabitan los relaves mineros debe abordarse desde diferentes\r\ndisciplinas. Por estos motivos, a trav\u00e9s de la interconexi\u00f3n de las\r\ndiversas capacidades de investigadores nacionales e\r\ninternacionales, el presente proyecto busca sentar las bases para\r\nla creaci\u00f3n de un Centro de Biolog\u00eda de Sistemas para el estudio\r\nde comunidades que habitan relaves mineros. A nivel de\r\ninvestigaci\u00f3n. el Centro se enfocar\u00e1 en: i) Caracterizar la\r\nestructura de las comunidades extrem\u00f3filas de los relaves. ii)\r\nIdentificar y validar de los potenciales metab\u00f3licos de las\r\ncomunidades y sus miembros. iii) Generar un registro y\r\nclasificaci\u00f3n de informaci\u00f3n - Bases de datos y colecci\u00f3n de\r\ncepas. iv) Desarrollo de biotecnolog\u00eda para aplicaciones en\r\nminer\u00eda. En definitiva, con un fuerte compromiso regional, el\r\nproyecto contempla abordar por primera vez desde una\r\nperspectiva multidisciplinaria e integral, el estudio de\r\ncomunidades de especies extrem\u00f3filas presentes en el relave\r\nCauquenes, sentando las bases para que el Centro de Biolog\u00eda de\r\nSistemas pueda en el corto plazo, proyectarse como un espacio\r\nreal para al estudio de microorganismos que habitan los relaves\r\nen Chile.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2021 - Diciembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>COES<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26989\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Violencias, securizaci\u00f3n y producci\u00f3n del orden social y del espacio urbano en campamentos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26989\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26989\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Materia Espec\u00edfica: El proyecto se focaliza en indagar de manera exploratoria sobre las violencias presentes en los asentamientos informales en Chile, en particular los campamentos, y centrar el an\u00e1lisis en su prevalencia, causas y\r\nla capacidad que las violencias tienen de producir el espacio urbano y el orden social.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2021 - Noviembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Colegio M\u00e9dico de Chile<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26816\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            La experiencia de trabajo de cuidados de los trabajadores de la salud en Chile durante la pandemia COVID-19 y su impacto en la salud mental\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26816\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26816\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Se propone la realizaci\u00f3n de un estudio de car\u00e1cter transversal con enfoque anal\u00edtico tem\u00e1tico, que utilizar\u00e1 entrevistas semi-estructuradas, en base al conocimiento emanado del estudio HEROES. Contar\u00e1 con mayoritaria participaci\u00f3n de profesionales m\u00e9dicos y m\u00e9dicas de la Regi\u00f3n Metropolitana. Su objetivo general ser\u00e1 comprender la experiencia subjetiva de m\u00e9dicos y m\u00e9dicas del sector p\u00fablico de salud respecto del trabajo de cuidados durante la pandemia COVID-19.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2021 - Diciembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26143\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Primeros pasos humanos en Am\u00e9rica del Sur: caminando entre Gonfoterios\u0094 \u0096 Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26143\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26143\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La Fundaci\u00f3n Palarq financia las excavaciones arqueol\u00f3gicas y paleontol\u00f3gicas de Tagua Tagua 3[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26114\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Creaci\u00f3n de im\u00e1genes de superresoluci\u00f3n ultras\u00f3nicas en placentas humanas ex vivo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26114\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26114\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26328\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Creaci\u00f3n de im\u00e1genes de superresoluci\u00f3n ultras\u00f3nicas en placentas humanas ex vivo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26328\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26328\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1211962<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2021 - Octubre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25996\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Effects of eccentric, concentric and eccentric\/concentric training on muscle function and mass, functional performance, cardiometabolic health, quality of life and molecular adaptations of skeletal muscle in COPD patients: a multicenter randomized trial\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25996\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25996\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Es proyecto busca comparar los  efectos de diversos programas de ejercicio f\u00edsico en diversos parametros pronosticos en pacientes con EPOC severo[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1211962<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2021 - Octubre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26138\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Effects of eccentric, concentric and eccentric\/concentric training on muscle function and mass, functional performance, cardiometabolic health, quality of life and molecular adaptations of skeletal muscle in COPD patients: a multicenter randomized trial\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26138\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26138\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Es proyecto busca comparar los  efectos de diversos programas de ejercicio f\u00edsico en diversos parametros pronosticos en pacientes con EPOC severo[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2021 - Septiembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio Federal Alem\u00e1n para la Colaboraci\u00f3n Econ\u00f3mica y el Desarrollo (BMZ) a trav\u00e9s de la Alianza Internacional contra los Riesgos Sanitarios en el Comercio de Vida Silvestre y coordinado por la GIZ (Gesellschaft f\u00fcr Internationale Zusammenarbeit)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26371\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26371\" aria-expanded=\"false\" aria-controls=\"collapse-26371\">\n                                            Knowledge, attitudes, and practices towards the risk of zoonotic diseases, wildlife trade and wildlife consumption in Latin America\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26371\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26371\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En el transcurso de este proyecto se recopila informaci\u00f3n que luego se someter\u00e1 a analisis respecto a lo conocimientos, actitudes y pr\u00e1cticas frente al riesgo de enfermedades zoon\u00f3ticas, comercio y consumo de vida silvestre en distintos paises participantes de Latino America.\r\nMinisterio Federal Alem\u00e1n para la Colaboraci\u00f3n Econ\u00f3mica y el Desarrollo (BMZ) a trav\u00e9s de la Alianza Internacional contra los Riesgos Sanitarios en el Comercio de Vida Silvestre y coordinado por la GIZ (Gesellschaft f\u00fcr Internationale Zusammenarbeit) con un importe total de 299.700\u0080.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2021 - Septiembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio Federal Alem\u00e1n para la Colaboraci\u00f3n Econ\u00f3mica y el Desarrollo (BMZ) a trav\u00e9s de la Alianza Internacional contra los Riesgos Sanitarios en el Comercio de Vida Silvestre y coordinado por la GIZ (Gesellschaft f\u00fcr Internationale Zusammenarbeit)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26662\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26662\" aria-expanded=\"false\" aria-controls=\"collapse-26662\">\n                                            Knowledge, attitudes, and practices towards the risk of zoonotic diseases, wildlife trade and wildlife consumption in Latin America\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26662\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26662\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En el transcurso de este proyecto se recopila informaci\u00f3n que luego se someter\u00e1 a analisis respecto a lo conocimientos, actitudes y pr\u00e1cticas frente al riesgo de enfermedades zoon\u00f3ticas, comercio y consumo de vida silvestre en distintos paises participantes de Latino America.\r\nMinisterio Federal Alem\u00e1n para la Colaboraci\u00f3n Econ\u00f3mica y el Desarrollo (BMZ) a trav\u00e9s de la Alianza Internacional contra los Riesgos Sanitarios en el Comercio de Vida Silvestre y coordinado por la GIZ (Gesellschaft f\u00fcr Internationale Zusammenarbeit) con un importe total de 299.700\u0080.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2021 - Septiembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio Federal Alem\u00e1n para la Colaboraci\u00f3n Econ\u00f3mica y el Desarrollo (BMZ) a trav\u00e9s de la Alianza Internacional contra los Riesgos Sanitarios en el Comercio de Vida Silvestre y coordinado por la GIZ (Gesellschaft f\u00fcr Internationale Zusammenarbeit)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26815\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26815\" aria-expanded=\"false\" aria-controls=\"collapse-26815\">\n                                            Knowledge, attitudes, and practices towards the risk of zoonotic diseases, wildlife trade and wildlife consumption in Latin America\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26815\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26815\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En el transcurso de este proyecto se recopila informaci\u00f3n que luego se someter\u00e1 a analisis respecto a lo conocimientos, actitudes y pr\u00e1cticas frente al riesgo de enfermedades zoon\u00f3ticas, comercio y consumo de vida silvestre en distintos paises participantes de Latino America.\r\nMinisterio Federal Alem\u00e1n para la Colaboraci\u00f3n Econ\u00f3mica y el Desarrollo (BMZ) a trav\u00e9s de la Alianza Internacional contra los Riesgos Sanitarios en el Comercio de Vida Silvestre y coordinado por la GIZ (Gesellschaft f\u00fcr Internationale Zusammenarbeit) con un importe total de 299.700\u0080.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2021 - Agosto 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Corporaci\u00f3n de Fomento de la Producci\u00f3n - CORFO<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26115\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Crea y Valida I+D+i Colaborativo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26115\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26115\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto que busca establecer los efectos de un suplemento en base a miel sobre la salud y el bienestar, as\u00ed como la respuesta al tratamiento en personas con \u00falcera g\u00e1stricas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2021 - Agosto 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Corporaci\u00f3n de Fomento de la Producci\u00f3n - CORFO<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26136\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Crea y Valida I+D+i Colaborativo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26136\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26136\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto que busca establecer los efectos de un suplemento en base a miel sobre la salud y el bienestar, as\u00ed como la respuesta al tratamiento en personas con \u00falcera g\u00e1stricas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2021 - Agosto 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Corporaci\u00f3n de Fomento de la Producci\u00f3n - CORFO<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26329\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Crea y Valida I+D+i Colaborativo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26329\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26329\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto que busca establecer los efectos de un suplemento en base a miel sobre la salud y el bienestar, as\u00ed como la respuesta al tratamiento en personas con \u00falcera g\u00e1stricas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 3220665<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26810\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Cuidados sociocomunitarios de personas con discapacidad en la regi\u00f3n de O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26810\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26810\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]N\u00famero de proyecto: 3220665[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Patrocinante<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 3220665<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26952\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Cuidados sociocomunitarios de personas con discapacidad en la regi\u00f3n de O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26952\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26952\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]N\u00famero de proyecto: 3220665[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26919\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            \u00bfExcelencia con inclusi\u00f3n?: efectos y estrategias de los colegios de alta exigencia ante las nuevas pol\u00edticas de admisi\u00f3n\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26919\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26919\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En 2017, Chile comenz\u00f3 la implementaci\u00f3n de la Ley de Inclusi\u00f3n Educativa (LIE) y, con ella, de un nuevo Sistema de Admisi\u00f3n Escolar (SAE), consistente en un sistema de postulaci\u00f3n en l\u00ednea con asignaci\u00f3n aleatoria que proh\u00edbe la selecci\u00f3n en la admisi\u00f3n a establecimientos que reciben financiaci\u00f3n estatal (aproximadamente 90% de las matr\u00edculas nacionales). Este art\u00edculo se basa en un estudio centrado en un peque\u00f1o subconjunto de establecimientos escolares categorizados como \u0093Escuelas de Alta Exigencia\u0094 (EAE). A las EAE se les permite mantener cierto grado de selectividad acad\u00e9mica para conservar su excelencia acad\u00e9mica, al mismo tiempo que incorporan lentamente la admisi\u00f3n abierta para incluir a estudiantes de or\u00edgenes sociales diversos sin consideraci\u00f3n de sus antecedentes acad\u00e9micos previos. \r\nEste estudio tiene por objetivo general estudiar el impacto de liceos de excelencia sobre las oportunidades educacionales de los estudiantes, as\u00ed como las pr\u00e1cticas de gesti\u00f3n de los establecimientos ante la nueva regulaci\u00f3n a sus tradicionales reglas de admisi\u00f3n, que suponen combinar excelencia con inclusi\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>SUSESO \u0096 Proyectos de Investigaci\u00f3n e Innovaci\u00f3n en prevenci\u00f3n de Accidentes del Trabajo y Enfermedades Profesionales<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26814\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Evaluaci\u00f3n de la efectividad de una intervenci\u00f3n multicomponente para mejorar los estilos de vida saludables y reducir el riesgo cardiovascular en trabajadores de empresas de una comuna rural\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26814\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26814\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Nuestro pa\u00eds tiene un gran desaf\u00edo para modificar estilos de vida saludables y reducir el riesgo cardiovascular.\r\nHasta la fecha, la mayor\u00eda de las intervenciones se han focalizado en aspectos o grupos espec\u00edficos, con efectos\r\nmuy limitados. Las experiencias m\u00e1s exitosas han sido aquellas que abordan comunidades completas, tal como lo demostr\u00f3 el proyecto desarrollado en la regi\u00f3n de North Karelia, Finlandia. Por otra parte, los organismos\r\nmultilaterales han se\u00f1alado que el lugar de trabajo juega un rol fundamental para modificar estos estilos de vida e indicadores de salud general, lo que contribuye a reducir accidentes y enfermedades profesionales.\r\nDado que en la comuna de Curaco de V\u00e9lez (Chilo\u00e9) se est\u00e1 iniciando un proyecto integral para mejorar los estilos de vida, esto ofrece una condici\u00f3n \u00f3ptimaa para realizar una prueba piloto en una empresa en ese lugar. Nos proponemos construir una intervenci\u00f3n multicomponente y adaptada culturalmente, que utilice una App nativa (construida ad hoc para este proyecto) como herramienta de apoyo, y evaluar su efectividad para mejorar estilos de vida saludables, reducir riesgo cardiovascular, mejorar la detecci\u00f3n y el control de Hipertensi\u00f3n Arterial y Diabetes Mellitus. Al mismo tiempo evaluaremos su implementaci\u00f3n, para un posible escalamiento futuro.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> MSM2021003<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2021 - Julio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26047\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Gesti\u00f3n Inteligente de Recursos H\u00eddricos para la Agricultura\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26047\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26047\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En este proyecto, se busca general nuevas tecnolog\u00edas que permitan mejorar el manejo de recursos h\u00eddricos en la sexta regi\u00f3n.\r\n\r\nDirector de l\u00ednea \"Gesti\u00f3n de Riego Intrapredial con Inteligencia Artificial\"[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> MSM2021003<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2021 - Julio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26280\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Gesti\u00f3n Inteligente de Recursos H\u00eddricos para la Agricultura\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26280\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26280\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En este proyecto, se busca general nuevas tecnolog\u00edas que permitan mejorar el manejo de recursos h\u00eddricos en la sexta regi\u00f3n.\r\n\r\nDirector de l\u00ednea \"Gesti\u00f3n de Riego Intrapredial con Inteligencia Artificial\"[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> MSM2021003<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2021 - Julio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26469\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Gesti\u00f3n Inteligente de Recursos H\u00eddricos para la Agricultura\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26469\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26469\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En este proyecto, se busca general nuevas tecnolog\u00edas que permitan mejorar el manejo de recursos h\u00eddricos en la sexta regi\u00f3n.\r\n\r\nDirector de l\u00ednea \"Gesti\u00f3n de Riego Intrapredial con Inteligencia Artificial\"[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> MSM2021003<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2021 - Julio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26494\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Gesti\u00f3n Inteligente de Recursos H\u00eddricos para la Agricultura\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26494\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26494\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En este proyecto, se busca general nuevas tecnolog\u00edas que permitan mejorar el manejo de recursos h\u00eddricos en la sexta regi\u00f3n.\r\n\r\nDirector de l\u00ednea \"Gesti\u00f3n de Riego Intrapredial con Inteligencia Artificial\"[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> MSM2021003<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2021 - Julio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26647\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Gesti\u00f3n Inteligente de Recursos H\u00eddricos para la Agricultura\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26647\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26647\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En este proyecto, se busca general nuevas tecnolog\u00edas que permitan mejorar el manejo de recursos h\u00eddricos en la sexta regi\u00f3n.\r\n\r\nDirector de l\u00ednea \"Gesti\u00f3n de Riego Intrapredial con Inteligencia Artificial\"[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> MSM2021003<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2021 - Julio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26661\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Gesti\u00f3n Inteligente de Recursos H\u00eddricos para la Agricultura\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26661\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26661\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En este proyecto, se busca general nuevas tecnolog\u00edas que permitan mejorar el manejo de recursos h\u00eddricos en la sexta regi\u00f3n.\r\n\r\nDirector de l\u00ednea \"Gesti\u00f3n de Riego Intrapredial con Inteligencia Artificial\"[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2021 - Julio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25989\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Creaci\u00f3n de im\u00e1genes de super-resoluci\u00f3n ultras\u00f3nicas en placentas humanas ex-vivo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25989\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25989\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2021 - Julio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26112\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Creaci\u00f3n de im\u00e1genes de super-resoluci\u00f3n ultras\u00f3nicas en placentas humanas ex-vivo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26112\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26112\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2021 - Julio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26517\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Creaci\u00f3n de im\u00e1genes de super-resoluci\u00f3n ultras\u00f3nicas en placentas humanas ex-vivo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26517\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26517\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2021 - Julio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26609\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Creaci\u00f3n de im\u00e1genes de super-resoluci\u00f3n ultras\u00f3nicas en placentas humanas ex-vivo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26609\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26609\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2021 - Octubre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26368\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Dise\u00f1o de una propuesta de educaci\u00f3n sexual integral en ni\u00f1os, ni\u00f1as y ni\u00f1es de 4 y 5 a\u00f1os.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26368\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26368\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La sexualidad seg\u00fan la OMS, (OMS, 2018) es definida como un aspecto central del ser humano, dentro de las dimensiones que abarca se encuentra, la reproducci\u00f3n, placer y\/o erotismo, v\u00ednculos afectivos y g\u00e9nero, a parte del car\u00e1cter inherente al ser humano, se destaca que se encuentra presente durante toda la vida, por esta raz\u00f3n se considera necesario que las estrategias para erradicar brechas de g\u00e9nero deben iniciarse en los primeros a\u00f1os de vida.\r\nHasta aqu\u00ed la mayor parte de los estudios de la tem\u00e1tica se relacionan con poblaci\u00f3n de adolescentes y\/o con la visi\u00f3n de cuidadores\/as poseen del desarrollo sexual afectivo de sus ni\u00f1os, ni\u00f1as y ni\u00f1es, sin embargo, existe incertidumbre en relaci\u00f3n a lo que saben actualmente ni\u00f1os, ni\u00f1as y ni\u00f1es en relaci\u00f3n a sexualidad y cuales han sido sus principales fuentes de informaci\u00f3n. En este contexto, se pretende dise\u00f1ar una propuesta de educaci\u00f3n sexual integral en ni\u00f1os, ni\u00f1as y ni\u00f1es de 4 y 5.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2021 - Julio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26623\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            PhenoBreed: Un prototipo de c\u00e1maras de bajo costo para el fenotipado de plantas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26623\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26623\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El aumento de los recursos tecnol\u00f3gicos y la automatizaci\u00f3n de los procesos agr\u00edcolas ha contribuido en gran medida al desarrollo de nuevas tecnolog\u00edas que permiten caracterizar y evaluar el fenotipo de las plantas. Espec\u00edficamente, las tecnolog\u00edas de fenotipado de plantas son muy importantes para acelerar los programas de\r\nmejoramiento en cultivos agron\u00f3micamente importantes, y contribuyen en el proceso de selecci\u00f3n para el desarrollo y posterior lanzamiento al mercado de nuevas variedades y cultivares. Los sistemas de visi\u00f3n unidimensionales (1D) y bidimensionales (2D) han sido una parte integral de la implementaci\u00f3n exitosa de la automatizaci\u00f3n agr\u00edcola y la rob\u00f3tica en los procesos agr\u00edcolas. Sin embargo, las t\u00e9cnicas basadas en im\u00e1genes en 2D son insuficientes para investigar las estructuras espaciales de las plantas. En este sentido, la reconstrucci\u00f3n por medio de im\u00e1genes 3D de plantas y la adquisici\u00f3n de su informaci\u00f3n espacial es una forma alternativa eficaz para resolver estos problemas. En este sentido, el objetivo del presente proyecto es obtener de forma autom\u00e1tica la estructura tridimensional del sistema de arquitectura de ra\u00edces de una planta e identificar par\u00e1metros morfol\u00f3gicos asociados con dicha estructura. Para ello se propone construir un prototipo, a partir de c\u00e1maras de bajo costo, para la reconstrucci\u00f3n automatizada de la estructura 3D de plantas, junto con la posterior detecci\u00f3n y medici\u00f3n de los rasgos morfol\u00f3gicos de esta misma.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2021 - Octubre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26660\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Dise\u00f1o de una propuesta de educaci\u00f3n sexual integral en ni\u00f1os, ni\u00f1as y ni\u00f1es de 4 y 5 a\u00f1os.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26660\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26660\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La sexualidad seg\u00fan la OMS, (OMS, 2018) es definida como un aspecto central del ser humano, dentro de las dimensiones que abarca se encuentra, la reproducci\u00f3n, placer y\/o erotismo, v\u00ednculos afectivos y g\u00e9nero, a parte del car\u00e1cter inherente al ser humano, se destaca que se encuentra presente durante toda la vida, por esta raz\u00f3n se considera necesario que las estrategias para erradicar brechas de g\u00e9nero deben iniciarse en los primeros a\u00f1os de vida.\r\nHasta aqu\u00ed la mayor parte de los estudios de la tem\u00e1tica se relacionan con poblaci\u00f3n de adolescentes y\/o con la visi\u00f3n de cuidadores\/as poseen del desarrollo sexual afectivo de sus ni\u00f1os, ni\u00f1as y ni\u00f1es, sin embargo, existe incertidumbre en relaci\u00f3n a lo que saben actualmente ni\u00f1os, ni\u00f1as y ni\u00f1es en relaci\u00f3n a sexualidad y cuales han sido sus principales fuentes de informaci\u00f3n. En este contexto, se pretende dise\u00f1ar una propuesta de educaci\u00f3n sexual integral en ni\u00f1os, ni\u00f1as y ni\u00f1es de 4 y 5.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2021 - Octubre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26813\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Dise\u00f1o de una propuesta de educaci\u00f3n sexual integral en ni\u00f1os, ni\u00f1as y ni\u00f1es de 4 y 5 a\u00f1os.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26813\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26813\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La sexualidad seg\u00fan la OMS, (OMS, 2018) es definida como un aspecto central del ser humano, dentro de las dimensiones que abarca se encuentra, la reproducci\u00f3n, placer y\/o erotismo, v\u00ednculos afectivos y g\u00e9nero, a parte del car\u00e1cter inherente al ser humano, se destaca que se encuentra presente durante toda la vida, por esta raz\u00f3n se considera necesario que las estrategias para erradicar brechas de g\u00e9nero deben iniciarse en los primeros a\u00f1os de vida.\r\nHasta aqu\u00ed la mayor parte de los estudios de la tem\u00e1tica se relacionan con poblaci\u00f3n de adolescentes y\/o con la visi\u00f3n de cuidadores\/as poseen del desarrollo sexual afectivo de sus ni\u00f1os, ni\u00f1as y ni\u00f1es, sin embargo, existe incertidumbre en relaci\u00f3n a lo que saben actualmente ni\u00f1os, ni\u00f1as y ni\u00f1es en relaci\u00f3n a sexualidad y cuales han sido sus principales fuentes de informaci\u00f3n. En este contexto, se pretende dise\u00f1ar una propuesta de educaci\u00f3n sexual integral en ni\u00f1os, ni\u00f1as y ni\u00f1es de 4 y 5.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2021 - Julio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26874\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            PhenoBreed: Un prototipo de c\u00e1maras de bajo costo para el fenotipado de plantas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26874\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26874\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El aumento de los recursos tecnol\u00f3gicos y la automatizaci\u00f3n de los procesos agr\u00edcolas ha contribuido en gran medida al desarrollo de nuevas tecnolog\u00edas que permiten caracterizar y evaluar el fenotipo de las plantas. Espec\u00edficamente, las tecnolog\u00edas de fenotipado de plantas son muy importantes para acelerar los programas de\r\nmejoramiento en cultivos agron\u00f3micamente importantes, y contribuyen en el proceso de selecci\u00f3n para el desarrollo y posterior lanzamiento al mercado de nuevas variedades y cultivares. Los sistemas de visi\u00f3n unidimensionales (1D) y bidimensionales (2D) han sido una parte integral de la implementaci\u00f3n exitosa de la automatizaci\u00f3n agr\u00edcola y la rob\u00f3tica en los procesos agr\u00edcolas. Sin embargo, las t\u00e9cnicas basadas en im\u00e1genes en 2D son insuficientes para investigar las estructuras espaciales de las plantas. En este sentido, la reconstrucci\u00f3n por medio de im\u00e1genes 3D de plantas y la adquisici\u00f3n de su informaci\u00f3n espacial es una forma alternativa eficaz para resolver estos problemas. En este sentido, el objetivo del presente proyecto es obtener de forma autom\u00e1tica la estructura tridimensional del sistema de arquitectura de ra\u00edces de una planta e identificar par\u00e1metros morfol\u00f3gicos asociados con dicha estructura. Para ello se propone construir un prototipo, a partir de c\u00e1maras de bajo costo, para la reconstrucci\u00f3n automatizada de la estructura 3D de plantas, junto con la posterior detecci\u00f3n y medici\u00f3n de los rasgos morfol\u00f3gicos de esta misma.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2021 - Abril 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26060\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Editoriales Independientes de la Regi\u00f3n del Libertador General Bernardo O\u0092Higgins: Emergencia, Tr\u00e1nsitos Hist\u00f3ricos, proyecciones y difusi\u00f3n\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26060\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26060\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2021 - Marzo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26244\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estudio de especies bacterianas con potenciales en biotecnolog\u00eda: Aplicaciones en miner\u00eda y agroindustria.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26244\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26244\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Identificaci\u00f3n de bacterias de ralves de la regi\u00f3n de O'Higgins para el estudio de posibles funciones biotecnol\u00f3gicas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2021 - Junio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26299\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Rol protector de aceite esencial de Origanum vulgare L. sobre la se\u00f1alizaci\u00f3n alterada de la insulina inducida por \u00e1cido palm\u00edtico en c\u00e9lulas adiposas humanas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26299\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26299\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetivo general de este proyecto es caracterizar la composici\u00f3n qu\u00edmica y el poder antioxidante del AE-O y evaluar su efecto sobre la alteraci\u00f3n inducida por AP en la v\u00eda PI3K\/Akt en adipocitos humanos SW872. Para ello, los objetivos espec\u00edficos de esta propuesta son: i) caracterizar la composici\u00f3n fitoqu\u00edmica y el poder antioxidante del AE-O, ii) evaluar la citotoxicidad in vitro del AE-O sobre adipocitos SW872, y iii) evaluar el efecto in vitro del AE-O sobre la alteraci\u00f3n de la v\u00eda de se\u00f1alizaci\u00f3n de la insulina PI3K\/Akt inducida por AP en adipocitos SW872. Para realizar estos objetivos, primero se obtendr\u00e1 el AE-O a trav\u00e9s de destilaci\u00f3n por vapor, y a continuaci\u00f3n se determinar\u00e1 la concentraci\u00f3n total de polifenoles mediante el m\u00e9todo Folin-Ciocalteu y su capacidad antioxidante analizada mediante el ensayo de DPPH, para luego estandarizar el aceite seg\u00fan su composici\u00f3n fitoqu\u00edmica evaluado por t\u00e9cnicas cromatogr\u00e1ficas. Para estudiar la citotoxicidad in vitro del aceite, se evaluar\u00e1 la viabilidad celular en adipocitos SW872 diferenciados in vitro tratados con distintas concentraciones del aceite. Para estudiar el efecto protector in vitro del AE-O contra la alteraci\u00f3n en la se\u00f1alizaci\u00f3n metab\u00f3lica de la insulina inducida por AP, se evaluar\u00e1 la activaci\u00f3n de la v\u00eda PI3K\/Akt por Western blot y la captaci\u00f3n de glucosa (an\u00e1logo fluorescente) inducida por insulina en adipocitos SW872 incubados o no con el AE-O.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2021 - Marzo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26385\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estudio de especies bacterianas con potenciales en biotecnolog\u00eda: Aplicaciones en miner\u00eda y agroindustria.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26385\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26385\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Identificaci\u00f3n de bacterias de ralves de la regi\u00f3n de O'Higgins para el estudio de posibles funciones biotecnol\u00f3gicas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2021 - Junio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26421\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Rol protector de aceite esencial de Origanum vulgare L. sobre la se\u00f1alizaci\u00f3n alterada de la insulina inducida por \u00e1cido palm\u00edtico en c\u00e9lulas adiposas humanas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26421\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26421\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetivo general de este proyecto es caracterizar la composici\u00f3n qu\u00edmica y el poder antioxidante del AE-O y evaluar su efecto sobre la alteraci\u00f3n inducida por AP en la v\u00eda PI3K\/Akt en adipocitos humanos SW872. Para ello, los objetivos espec\u00edficos de esta propuesta son: i) caracterizar la composici\u00f3n fitoqu\u00edmica y el poder antioxidante del AE-O, ii) evaluar la citotoxicidad in vitro del AE-O sobre adipocitos SW872, y iii) evaluar el efecto in vitro del AE-O sobre la alteraci\u00f3n de la v\u00eda de se\u00f1alizaci\u00f3n de la insulina PI3K\/Akt inducida por AP en adipocitos SW872. Para realizar estos objetivos, primero se obtendr\u00e1 el AE-O a trav\u00e9s de destilaci\u00f3n por vapor, y a continuaci\u00f3n se determinar\u00e1 la concentraci\u00f3n total de polifenoles mediante el m\u00e9todo Folin-Ciocalteu y su capacidad antioxidante analizada mediante el ensayo de DPPH, para luego estandarizar el aceite seg\u00fan su composici\u00f3n fitoqu\u00edmica evaluado por t\u00e9cnicas cromatogr\u00e1ficas. Para estudiar la citotoxicidad in vitro del aceite, se evaluar\u00e1 la viabilidad celular en adipocitos SW872 diferenciados in vitro tratados con distintas concentraciones del aceite. Para estudiar el efecto protector in vitro del AE-O contra la alteraci\u00f3n en la se\u00f1alizaci\u00f3n metab\u00f3lica de la insulina inducida por AP, se evaluar\u00e1 la activaci\u00f3n de la v\u00eda PI3K\/Akt por Western blot y la captaci\u00f3n de glucosa (an\u00e1logo fluorescente) inducida por insulina en adipocitos SW872 incubados o no con el AE-O.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26988\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Representaci\u00f3n de la protesta pol\u00edtica desde el campo jur\u00eddico: el caso del  ciclo de protestas abierto en chile el 2019\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26988\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26988\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Materia Espec\u00edfica: El proyecto busca comprender las formas en que se construye el significado del derecho a la protesta desde el campo jur\u00eddico y las disputas en torno a dicho proceso de construcci\u00f3n[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 20SN-151304.<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2021 - Marzo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Corporaci\u00f3n de Fomento de la Producci\u00f3n - CORFO<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27053\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Producci\u00f3n de prote\u00ednas nanoestructuradas como inmunoestimulantes contra Piscirickettsiosis.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27053\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27053\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La Piscirickettsiosis es una grave enfermedad bacteriana que resulta en altos niveles de mortalidad en diferentes especies de salm\u00f3nidos. Las p\u00e9rdidas totales, incluidos los costos de vacunaci\u00f3n y los tratamientos antimicrobianos se han estimado en alrededor de $ 450 millones de d\u00f3lares por a\u00f1o en Chile. Desafortunadamente, las vacunas contra este pat\u00f3geno han mostrado ser poco efectivas para prevenir esta enfermedad, lo que se ha asociado a fen\u00f3menos de coinfecci\u00f3n de Caligus, variabilidad del pat\u00f3geno y del hospedero. Recientes estudios muestran, adem\u00e1s, que los mecanismos de respuesta inmune innata son los responsables de otorgar protecci\u00f3n a los peces frente a un desaf\u00edo con esta bacteria. De esta manera, la falta de tratamientos eficaces contra Piscirickettsia salmonis fundamentan la necesidad de buscar nuevas alternativas de tratamientos profil\u00e1cticos, las que deber\u00edan estar orientados a reforzar el sistema inmune innato del hospedador. \r\nEn base a estas necesidades nosotros proponemos evaluar prote\u00ednas nanoestructuradas, tambi\u00e9n conocidas como cuerpos de inclusi\u00f3n como inmunoestimulantes para el control de P. salmonis en salm\u00f3n del Atl\u00e1ntico (Salmo salar). Estas prote\u00ednas nanoestructuradas pueden expresar cualquier prote\u00edna con una funci\u00f3n de inter\u00e9s, la cual es liberada gradualmente en el tiempo. Adem\u00e1s, son muy estables y resisten duras condiciones fisicoqu\u00edmicas manteniendo su funcionalidad por lo que no es necesario su encapsulaci\u00f3n. Debido a que la producci\u00f3n de estas prote\u00ednas es altamente escalable en biorreactores bacterianos surgen entonces como una herramienta de biotecnolog\u00eda viable de llegar a ser una soluci\u00f3n comercial. Recientemente he evaluado con \u00e9xito el uso de prote\u00ednas nanoestructuradas de citoquinas como inmunoestimulantes en trucha arco\u00edris (Onchorhynchuss mykiss) y el pez cebra (Danio rerio). La prueba de concepto de esta tecnolog\u00eda mostr\u00f3 que los cuerpos de inclusi\u00f3n pueden estimular una respuesta inmune en macr\u00f3fagos de trucha arco\u00edris. Adem\u00e1s, las prote\u00ednas nanoestructuradas administrados por v\u00eda intraperitoneal protegen al pez cebra frente a una infecci\u00f3n bacteriana letal y al ser administrados oralmente son absorbidos por c\u00e9lulas presentes en la mucosa intestinal.\r\nEn base a esto, proponemos como proyecto desarrollar prote\u00ednas nanoestructuradas como inmunoestimulantes contra Piscirickettsia, para ello contaremos con la asesor\u00eda t\u00e9cnica de tres laboratorios de la PUCV. Como primer objetivo realizaremos la clonaci\u00f3n de los genes que expresan las prote\u00ednas de inter\u00e9s y la producci\u00f3n de los pl\u00e1smidos para ser expresados en bacterias. Este objetivo se llevar\u00e1 a cabo en el Laboratorio de Gen\u00e9tica y Gen\u00f3mica Aplicada. En el segundo objetivo, produciremos las prote\u00ednas recombinantes con la asesor\u00eda t\u00e9cnica y en las instalaciones del Laboratorio de Cultivo de C\u00e9lulas Microbianas. Este grupo es experto en la producci\u00f3n de prote\u00ednas recombinantes en biorreactores de bacterias. Como tercer objetivo cuantificaremos y caracterizaremos las prote\u00ednas producidas con la asesor\u00eda y en el laboratorio del Grupo de Marcadores Inmunol\u00f3gicos de Organismos Acu\u00e1ticos. Este laboratorio es especialista en la purificaci\u00f3n, cuantificaci\u00f3n y caracterizaci\u00f3n de prote\u00ednas. Adem\u00e1s, contaremos con la asesor\u00eda del Laboratorio de Gen\u00e9tica y Gen\u00f3mica Aplicada en cuanto a c\u00f3mo dar continuidad al presente proyecto e introducir el producto en la industria. Nosotros esperamos como resultado de este proyecto desarrollar prote\u00ednas nanoestructuradas que sean administradas a peces como inmunoestimulantes contra Piscirickettsia. El desarrollo de un m\u00e9todo profil\u00e1ctico efectivo contra P. salmonis permitir\u00e1 disminuir las p\u00e9rdidas econ\u00f3micas asociadas a la Piscirickettsiosis y disminuir el uso excesivo de antibi\u00f3ticos en la industria de cultivo de salmones en Chile.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2021 - Enero 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Secretaria Regional Ministerial de las Culturas, las Artes y los Patrimonios de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26073\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26073\" aria-expanded=\"false\" aria-controls=\"collapse-26073\">\n                                            Estudio sobre Educaci\u00f3n Art\u00edstica en el Sistema Educativo Formal y no Formal de la regi\u00f3n del Libertador General Bernardo O\u0092Higgins Etapa II\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26073\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26073\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El presente estudio tiene como prop\u00f3sito realizar un levantamiento de datos actualizado sobre el estado de la Educaci\u00f3n Art\u00edstica en el sistema educativo formal, escuelas municipales, y espacios no formales de la Regi\u00f3n del Libertador Bernardo O\u0092Higgins.\r\nLa muestra final se compone de 104 escuelas municipales de la regi\u00f3n de O\u0092Higgins representativas de las tres provincias. A su vez, la muestra incluye a profesores\/as (80), artistas-educadores de Talleres Mineduc, talleristas Cecrea y Acciona).[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2021 - Octubre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>DAAD - Alemania<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26683\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            ECOH: Environment Care with a One Health approach\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26683\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26683\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The environment can be described as indispensable as it houses all life on earth, and evidence suggests that activities in interaction with nature not only provide physical and psychological benefits but also socially and economically.\r\n\r\nNonetheless, we are currently confronted with many environmental challenges, including climate change, loss of biodiversity and degradation of natural habitats, which have adverse health outcomes for animals, humans and our shared environment. Furthermore, regarding the COVID-19 pandemic, additional threats have emerged such as an increase in the use and disposal of plastic products for medical and non-medical applications and the amount of packaging used to deliver food and groceries to residences, leading to significant challenges in handling solid and hazardous medical wastes. This could become a crucial concern in the medium or long term, whilst aggravating the already existing issues, especially in countries with inadequate waste management systems.\r\n\r\nRecognizing this, environmental education has become more relevant than ever in ensuring a sustainable future by promoting responsible decision-making at the individual, institutional and community levels. The strengthening of environmental literacy through formal and informal educational strategies at different stages of the life course, considering day-to-day situations, will eventually allow for the development of capacities in the population, thereby conserving our shared environment.\r\nProject aim:\r\n\r\nThe project's main objective, therefore, is to empower the community for environmental care through educational strategies based on local needs in Guatemala and Bolivia.\r\n\r\nThis is to be achieved using a Participatory Action Research (PAR) approach by forming a multidisciplinary and intersectoral working group that includes professionals from the academy and representatives from diverse sectors like education, work, transportation, legislators and civil society. The project also follows a spiral approach, focusing on a problem and continuing with planning, action, observation and critical reflection, giving rise to a new progressive cycle. To better disseminate the project and population adherence, a digital platform app is to be designed to make available all the education material and specific guides that support this process.\r\n\r\nUltimately, creating awareness and educating, based on evidence, about our actions' impact will allow a better co-existence and promote sustainable development, sustainable use and care of natural resources when considering practices in rural and urban communities[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2021 - Octubre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>DAAD - Alemania<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26684\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Stingless BEEs as an ecological, Social capital and public health richness\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26684\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26684\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Stingless bees (Apidae: Meliponini) play a substantial role in the ecology, economy, and culture of many communities, especially in South America. They act as the main pollinators for many native florae and cultivated tropical plants. Their products such as honey, pollen, propolis and cerumen have also been used as a source of income for generations while creating an imprint on the culture of native communities.\r\n\r\nNevertheless, in recent decades, stingless bees currently face several environmental threats including the extensive deforestation of native forests, accelerated expansion of urban areas, excessive use of pesticides and fertilizers, agriculture intensification and the introduction\/spread of exotic competing bee species.\r\n\r\nIn this context, meliponiculture \u0096 i.e., keeping stingless bees for their products \u0096 is becoming more important for research not only as an optimal strategy for the conservation of bees and their environment but also for their economic value. In general, meliponiculture also promotes a variety of good environmental practices from different viewpoints in the society, maintains the traditional knowledge of native beekeeping and generates a link with innovation and scientific development. In Bolivia, meliponiculture remains an incipient activity although many indigenous communities have an ancient relationship with stingless bees. In Guatemala, the Maya tribe have also practiced meliponiculture for many years. Nevertheless, traditional knowledge is getting lost over time which must be recovered and supported by new techniques to generate a successful practice of beekeeping.\r\nProject aim:\r\n\r\nConsidering this, the project, therefore, aims to optimize the sustainable development of meliponiculture. This is to be achieved by documenting its traditional use in health while promoting good practices and commercialization to have a positive, direct impact over ecosystems as well as human health in cultural landscapes in indigenous communities in Bolivia and Guatemala.\r\n\r\nFor this, an interdisciplinary methodology is to be designed, which consists of a research component and educational interventions at the various processes of the production chain of meliponiculture: from the producers to consumers. Ultimately, the SBEES project is relevant, taking into account the One Health vision, as it seeks to promote a sustainable interaction between stingless bees, humans and the environment.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2021 - Abril 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad Diego Portales<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26765\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Evaluaci\u00f3n de los aprendizajes en investigaci\u00f3n en estudiantes de las Facultades de Psicolog\u00eda y Ciencias Sociales e Historia. La experiencia del proyecto \u0093Legitimidad de Carabineros: violencia, derechos humanos y control social&#8221;\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26765\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26765\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El presente proyecto pretende continuar y ampliar este ejercicio de desarrollo de habilidades de investigaci\u00f3n a partir de la participaci\u00f3n en el proyecto de investigaci\u00f3n. Espec\u00edficamente, se buscar\u00e1 replicar el ejercicio, pero esta vez en el marco de un proceso de evaluaci\u00f3n del mismo. A su vez, se pretende extender el ejercicio para considerar tambi\u00e9n a estudiantes de la Facultad de Ciencias Sociales e Historia. De esta forma, el proyecto busca explorar la relevancia de esta experiencia, durante su desarrollo en el a\u00f1o acad\u00e9mico 2021, como una estrategia de ense\u00f1anza-aprendizaje relevante en el proceso formativo.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2021 - Diciembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26144\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Primeros pasos humanos en Am\u00e9rica del Sur: caminando entre Gonfoterios\u0094 \u0096 Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26144\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26144\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La Fundaci\u00f3n financi\u00f3 las excavaciones arqueol\u00f3gicas y paleontol\u00f3gicas del yacimiento Tagua Tagua 3[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26648\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Stochasticity aspects in bilevel games and applications to water resource management\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26648\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26648\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 3210735<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2021 - Abril 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26652\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Stochasticity aspects in bilevel games and applications to water resource management\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26652\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26652\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Stochasticity in optimization and game theory is a very important aspect to model more accurately real-world problems in many different areas (see for instance [6]). In optimization problems as well as in one-level games, namely, Nash equilibrium problems, stochasticity aspects have received quite a lot of attention for a while and have also been well studied [22]. However, for the branch of bilevel games quite few studies have included in their analysis stochastic aspects in their models. \r\nA bilevel game is basically to split a finite set of players into two levels: the leaders or upper-level players, and the followers or lower-level players. In the model, the followers react in a passive way to the leaders' actions, while the\r\nleaders compete in the upper level trying to actively anticipate the followers' reaction. Moreover, in each level, the interaction is non-cooperative as in Nash equilibrium problems. Bilevel games have been recognized as one of the most complex and at the same time very useful models in the literature [17].\r\nBilevel games, and more precisely the problem of the leaders in a bilevel game, face an ambiguity\/uncertainty whenever the followers' reaction is not necessarily uniquely determined for each leaders' decision. To deal with this ambiguity two main approaches are well-known the optimistic and the pessimistic. The weakness of these two approaches is that both are quite extreme and the optimistic one lacks of real modeling foundations, putting the leaders in a quite naive position.\r\nRecently, in [9] a general stochastic approach has been proposed to solve this ambiguity, which is seen as an uncertainty of the problem, providing also a specific approach that seems to be more reasonable than the optimistic one, from a modeling point of view. The stochasticity in the stochastic approach is an endogenous one since it corresponds to a decision-dependent uncertainty [1, 23].\r\nBut, of course, stochasticity might also come from an exogenous side, that is, when some of the parameters defining the game, such as future demand and prices, 1 forecasts of winds and clouds, are uncertain and possibly follow some probability distribution. This has been considered in [34, 12, 13, 16].\r\nIn the second part of the project, which is the applied part, we are interested in using the developed theoretical framework of bilevel games with stochastic aspects to a problem of contaminated water resource management, which has high levels of stochasticity. \r\nThe scarcity of water resource and its efficient use has been recognized as an extremely important problem in Chile and the whole world, for agricultural, industrial, and human use. Moreover, after any use, there is an outflow of water\r\nwhich has generally more contaminants than the inflow. Depending on the type and quantity of contaminants the outflow of water could be reused, but sometimes giving less profit to the entity. The general situation is full of uncertainties, since the entities do not share their information. Moreover, the main source of information for us will be\r\nmeasurements on the quality of water at different strategic points and punctual events of contamination registered by inspection, which is simply a qualitative data.\r\nTherefore, we propose first to apply predictive models and machine learning to do inverse engineering in order to understand the game played by the different actors. Then we want to study the underlying one-level game and study the design of mechanisms (bilevel game) so that we can move the equilibrium to a desired goal. In a somehow similar spirit, in [30, 31, 10] game theory techniques have been used to analyze the behavior of companies sharing contaminated water in the context of eco-industrial parks, while in [36] also a bilevel model is used for a water resource optimal allocation problem.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Patrocinante<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 3210735<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2021 - Abril 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26658\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Stochasticity aspects in bilevel games and applications to water resource management\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26658\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26658\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Stochasticity in optimization and game theory is a very important aspect to model more accurately real-world problems in many different areas (see for instance [6]). In optimization problems as well as in one-level games, namely, Nash equilibrium problems, stochasticity aspects have received quite a lot of attention for a while and have also been well studied [22]. However, for the branch of bilevel games quite few studies have included in their analysis stochastic aspects in their models. \r\nA bilevel game is basically to split a finite set of players into two levels: the leaders or upper-level players, and the followers or lower-level players. In the model, the followers react in a passive way to the leaders' actions, while the\r\nleaders compete in the upper level trying to actively anticipate the followers' reaction. Moreover, in each level, the interaction is non-cooperative as in Nash equilibrium problems. Bilevel games have been recognized as one of the most complex and at the same time very useful models in the literature [17].\r\nBilevel games, and more precisely the problem of the leaders in a bilevel game, face an ambiguity\/uncertainty whenever the followers' reaction is not necessarily uniquely determined for each leaders' decision. To deal with this ambiguity two main approaches are well-known the optimistic and the pessimistic. The weakness of these two approaches is that both are quite extreme and the optimistic one lacks of real modeling foundations, putting the leaders in a quite naive position.\r\nRecently, in [9] a general stochastic approach has been proposed to solve this ambiguity, which is seen as an uncertainty of the problem, providing also a specific approach that seems to be more reasonable than the optimistic one, from a modeling point of view. The stochasticity in the stochastic approach is an endogenous one since it corresponds to a decision-dependent uncertainty [1, 23].\r\nBut, of course, stochasticity might also come from an exogenous side, that is, when some of the parameters defining the game, such as future demand and prices, 1 forecasts of winds and clouds, are uncertain and possibly follow some probability distribution. This has been considered in [34, 12, 13, 16].\r\nIn the second part of the project, which is the applied part, we are interested in using the developed theoretical framework of bilevel games with stochastic aspects to a problem of contaminated water resource management, which has high levels of stochasticity. \r\nThe scarcity of water resource and its efficient use has been recognized as an extremely important problem in Chile and the whole world, for agricultural, industrial, and human use. Moreover, after any use, there is an outflow of water\r\nwhich has generally more contaminants than the inflow. Depending on the type and quantity of contaminants the outflow of water could be reused, but sometimes giving less profit to the entity. The general situation is full of uncertainties, since the entities do not share their information. Moreover, the main source of information for us will be\r\nmeasurements on the quality of water at different strategic points and punctual events of contamination registered by inspection, which is simply a qualitative data.\r\nTherefore, we propose first to apply predictive models and machine learning to do inverse engineering in order to understand the game played by the different actors. Then we want to study the underlying one-level game and study the design of mechanisms (bilevel game) so that we can move the equilibrium to a desired goal. In a somehow similar spirit, in [30, 31, 10] game theory techniques have been used to analyze the behavior of companies sharing contaminated water in the context of eco-industrial parks, while in [36] also a bilevel model is used for a water resource optimal allocation problem.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 3210502<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2021 - Abril 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27052\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Cuerpos de inclusi\u00f3n como inmunoestimulantes de administraci\u00f3n oral para el control de Piscirickettsia salmonis en Salm\u00f3n del Atl\u00e1ntico.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27052\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27052\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La Piscirickettsiosis es una grave enfermedad bacteriana que resulta en altos niveles de mortalidad en diferentes especies de salm\u00f3nidos. Las p\u00e9rdidas totales, incluidos los costos de vacunaci\u00f3n y los tratamientos antimicrobianos se han estimado en alrededor de $ 450 millones de d\u00f3lares por a\u00f1o. Desafortunadamente, las vacunas contra este pat\u00f3geno han mostrado ser poco efectivas para prevenir esta enfermedad, lo que se ha asociado seg\u00fan estudios de nuestro laboratorio a fen\u00f3menos de coinfecci\u00f3n de Caligus, variabilidad del pat\u00f3geno y del hospedero. Recientes estudios muestran, adem\u00e1s, que los mecanismos de respuesta inmune innata son los responsables de otorgar protecci\u00f3n a los peces frente a un desaf\u00edo con esta bacteria. De esta manera, la falta de tratamientos eficaces contra Piscirickettsia salmonis fundamentan la necesidad de buscar nuevas alternativas de tratamientos profil\u00e1cticos, las que deber\u00edan estar orientados a reforzar el sistema inmune innato del hospedador. \r\nEn base a estas necesidades nosotros proponemos evaluar cuerpos de inclusi\u00f3n como inmunoestimulantes de administraci\u00f3n oral para el control de P. salmonis en salm\u00f3n del Atl\u00e1ntico (Salmo salar). Los cuerpos de inclusi\u00f3n son agregados de prote\u00ednas recombinantes nanoestructuradas funcionales expresados usualmente en el citoplasma de bacterias recombinantes. Los cuerpos de inclusi\u00f3n pueden expresar cualquier prote\u00edna con una funci\u00f3n de inter\u00e9s, la cual es liberada gradualmente en el tiempo. Adem\u00e1s, son muy estables y resisten duras condiciones fisicoqu\u00edmicas manteniendo su funcionalidad por lo que no es necesario su encapsulaci\u00f3n. Debido a que la producci\u00f3n de los cuerpos de inclusi\u00f3n es altamente escalable en biorreactores bacterianos surgen entonces como una herramienta de biotecnolog\u00eda susceptible de llegar a ser una soluci\u00f3n comercial. Recientemente he evaluado con \u00e9xito el uso de cuerpos de inclusi\u00f3n de citoquinas como inmunoestimulantes en trucha arco\u00edris (Onchorhynchuss mykiss) y el pez cebra (Danio rerio). La prueba de concepto de esta tecnolog\u00eda mostr\u00f3 que los cuerpos de inclusi\u00f3n pueden estimular una respuesta inmune en macr\u00f3fagos de trucha arco\u00edris. Adem\u00e1s, los cuerpos de inclusi\u00f3n administrados por v\u00eda intraperitoneal protegen al pez cebra frente a una infecci\u00f3n bacteriana letal y al ser administrados oralmente son absorbidos por c\u00e9lulas presentes en la mucosa intestinal.\r\nPostulamos como hip\u00f3tesis que los cuerpos de inclusi\u00f3n administrados por v\u00eda oral otorgan protecci\u00f3n al salm\u00f3n del atl\u00e1ntico contra P. salmonis. Como primer objetivo de este estudio proponemos realizar la producci\u00f3n y caracterizaci\u00f3n de los cuerpos de inclusi\u00f3n de dos prote\u00ednas relacionadas al sistema inmune innato de salm\u00f3n del Atl\u00e1ntico. En el segundo objetivo, evaluaremos la capacidad de inmunomodulaci\u00f3n del sistema inmune por parte de los cuerpos de inclusi\u00f3n al ser administrados en diferentes dosis a trav\u00e9s de la intubaci\u00f3n de los peces. Para ello usaremos RT-qPCR donde analizaremos la capacidad moduladora de los cuerpos de inclusi\u00f3n a trav\u00e9s de la expresi\u00f3n g\u00e9nica de citoquinas proinflamatorias (TNF&#945;, IL-1&#946;, IFN&#947;), antiinflamatorias (IL-10), enzima proinflamatoria (COX-2), y receptor tipo Toll (TLR9). Tambi\u00e9n analizaremos TNF&#945; e IL-10 a trav\u00e9s de ELISA. Igualmente, se analizar\u00e1 si los cuerpos de inclusi\u00f3n marcados con un fluor\u00f3foro son endocitados por c\u00e9lulas intestinales y si son trasladados al bazo a trav\u00e9s de citometr\u00eda de flujo. En el tercer objetivo, analizaremos la eficacia de los cuerpos de inclusi\u00f3n para el control de P. salmonis en salm\u00f3n del Atl\u00e1ntico administrados a trav\u00e9s del alimento en un desaf\u00edo experimental. Se evaluar\u00e1 a trav\u00e9s de t\u00e9cnicas moleculares (RT-qPCR y ELISA) citoquinas proinflamatorias, antiinflamatorias, enzima proinflamatoria, y receptor tipo Toll para analizar la capacidad inmunomoduladora de los cuerpos de inclusi\u00f3n durante un desaf\u00edo bacteriano. Asimismo, evaluaremos sobrevivencia, carga de P. salmonis y necropsia de los tejidos. Nosotros esperamos como resultado de esta investigaci\u00f3n que los cuerpos de inclusi\u00f3n aumenten la sobrevivencia de salm\u00f3n del Atl\u00e1ntico frente a un desaf\u00edo de P. salmonis. El desarrollo de un m\u00e9todo profil\u00e1ctico efectivo contra P. salmonis permitir\u00e1 disminuir las p\u00e9rdidas econ\u00f3micas asociadas a la Piscirickettsiosis y disminuir el uso excesivo de antibi\u00f3ticos en la industria de cultivo de salmones en Chile.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2021 - Mayo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Vinculaci\u00f3n Ciencia-Empresa VCE 200002<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26013\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Generaci\u00f3n de capital social entre los productores ap\u00edcolas de la regi\u00f3n y la Universidad de O\u0092Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26013\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26013\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Participaci\u00f3n en el rol de acad\u00e9mica- Investigadora experta en entomolog\u00eda dentro del Comit\u00e9 de coordinaci\u00f3n regional\r\n(no est\u00e1 el rol definido por eso aparece como co-inv))\r\n\r\nObjetivo general del proyecto\r\nDise\u00f1ar e implementar una estrategia transdisciplinaria de vinculaci\u00f3n entre\r\nlos apicultores de la regi\u00f3n y la Universidad de O\u0092Higgins, que permita construir una\r\n\u0093Hoja de Ruta\u0094 para resolver las brechas existentes en el sector y definir las l\u00edneas de\r\ninvesDgaci\u00f3n aplicada a desarrollarse[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2021 - Mayo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Vinculaci\u00f3n Ciencia-Empresa VCE 200002<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26425\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Generaci\u00f3n de capital social entre los productores ap\u00edcolas de la regi\u00f3n y la Universidad de O\u0092Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26425\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26425\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Participaci\u00f3n en el rol de acad\u00e9mica- Investigadora experta en entomolog\u00eda dentro del Comit\u00e9 de coordinaci\u00f3n regional\r\n(no est\u00e1 el rol definido por eso aparece como co-inv))\r\n\r\nObjetivo general del proyecto\r\nDise\u00f1ar e implementar una estrategia transdisciplinaria de vinculaci\u00f3n entre\r\nlos apicultores de la regi\u00f3n y la Universidad de O\u0092Higgins, que permita construir una\r\n\u0093Hoja de Ruta\u0094 para resolver las brechas existentes en el sector y definir las l\u00edneas de\r\ninvesDgaci\u00f3n aplicada a desarrollarse[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2021 - Abril 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26176\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Interactive effect of organic-mineral amendments and \u0093core microbiome\u0094 in restoration of abandoned mine tailings: promoting ecological processes and natural resilience\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26176\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26176\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Mining activities have discharged large amounts of wastes or mine tailings to the environment, which represent an important environmental issue. Mine tailings are mainly characterised by poor physicochemical properties that limit the plant establishment and development. The most negative property in these mine wastes is the high content of metals and metalloids [metal(loid)s], which are often highly toxic due to acid pH that increases metal(loid) bioavailability. This negatively affects living organisms and ecological functioning since soil microorganisms are pioneer colonisers that mediate the plant establishment. Also, mine tailings are usually deposited in abandoned locations of large land cover; from where, due to their physical characteristics, they can be transported by air and water, affecting communities and the environment in surrounding areas. There are several industrial strategies focused on the physical and chemical management of mine tailings, but these are highly expensive and occasionally not effective. These strategies have not been suitable techniques to reduce negative impacts of mine tailings on the environment. In this context, biological approaches, such as phytoremediation, have been proposed as more appropriate strategies due to low cost, easy applicability, and promising results. Nevertheless, most of the studies focused on phytoremediation of mine tailings, especially Chilean studies, have been performed in laboratory conditions. Although these studies show promising conclusions, in many cases unsuccessful results are obtained at field conditions, mainly due to laboratory experiments do not consider the dynamic field variability and potential ecological interactions.\r\nBased on the above, the proposed research aims to evaluate the effect of the initial addition of organic-mineral amendments and the bioaugmentation of microbial communities with \u0093core microbiome\u0094 from the root-zone of native herbaceous on the growth and development of native plants and microbial communities at copper mine tailings. We hypothesise that the growth and development of native plants in mine tailings will be promoted by the improvement of physicochemical properties of modified mine tailings (incipient technosols) through the addition of organic-mineral amendments, and the bioaugmentation of microbial communities with \u0093core microbiome\u0094 involved in plant fitness obtained from copper mine tailings and surrounding soils.\r\nTo evaluate the mentioned hypothesis, this study will be executed in three phases: 1) Initial field characterisation: this will be done for mine tailings and soils under sclerophyllous forest; 2) Collection and recruitment of \u0093core microbiome\u0094: this will study the composition, function, and interactions of \u0093core microbiome\u0094 obtained from the root-zone of native herbaceous established on mine tailings and soils under sclerophyllous forest, by which a laboratory-scale assay it is needed to produce inoculum of such ecological units (cores); 3) Restoration field experiment: this consists on the field establishment of native herbaceous species by bioaugmentation with \u0093core microbiome\u0094 from root-zone mine tailings and root-zone soil on incipient technosols produced by the addition of organic-mineral amendments on mine tailings. These phases are designed to be performed in three years.\r\nThis study can provide insights of the promotion of ecological process and natural resilience on microbial communities of mine tailings and surroundings, which can allow the initial plant establishment a development for later possible plant recruitment from the native sclerophyllous forest. This would also evaluate whether mine tailings can be in situ managed instead of been totally removed, which implies high costs and workflow to enterprises. Additionally, this study would represent the first approach of the evaluation of the biological functioning and composition of microbial communities from root-zone mine tailings in Chile, from its current state to the subsequent restoration process.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Patrocinante<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2021 - Abril 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26773\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Interactive effect of organic-mineral amendments and \u0093core microbiome\u0094 in restoration of abandoned mine tailings: promoting ecological processes and natural resilience\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26773\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26773\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Mining activities have discharged large amounts of wastes or mine tailings to the environment, which represent an important environmental issue. Mine tailings are mainly characterised by poor physicochemical properties that limit the plant establishment and development. The most negative property in these mine wastes is the high content of metals and metalloids [metal(loid)s], which are often highly toxic due to acid pH that increases metal(loid) bioavailability. This negatively affects living organisms and ecological functioning since soil microorganisms are pioneer colonisers that mediate the plant establishment. Also, mine tailings are usually deposited in abandoned locations of large land cover; from where, due to their physical characteristics, they can be transported by air and water, affecting communities and the environment in surrounding areas. There are several industrial strategies focused on the physical and chemical management of mine tailings, but these are highly expensive and occasionally not effective. These strategies have not been suitable techniques to reduce negative impacts of mine tailings on the environment. In this context, biological approaches, such as phytoremediation, have been proposed as more appropriate strategies due to low cost, easy applicability, and promising results. Nevertheless, most of the studies focused on phytoremediation of mine tailings, especially Chilean studies, have been performed in laboratory conditions. Although these studies show promising conclusions, in many cases unsuccessful results are obtained at field conditions, mainly due to laboratory experiments do not consider the dynamic field variability and potential ecological interactions.\r\nBased on the above, the proposed research aims to evaluate the effect of the initial addition of organic-mineral amendments and the bioaugmentation of microbial communities with \u0093core microbiome\u0094 from the root-zone of native herbaceous on the growth and development of native plants and microbial communities at copper mine tailings. We hypothesise that the growth and development of native plants in mine tailings will be promoted by the improvement of physicochemical properties of modified mine tailings (incipient technosols) through the addition of organic-mineral amendments, and the bioaugmentation of microbial communities with \u0093core microbiome\u0094 involved in plant fitness obtained from copper mine tailings and surrounding soils.\r\nTo evaluate the mentioned hypothesis, this study will be executed in three phases: 1) Initial field characterisation: this will be done for mine tailings and soils under sclerophyllous forest; 2) Collection and recruitment of \u0093core microbiome\u0094: this will study the composition, function, and interactions of \u0093core microbiome\u0094 obtained from the root-zone of native herbaceous established on mine tailings and soils under sclerophyllous forest, by which a laboratory-scale assay it is needed to produce inoculum of such ecological units (cores); 3) Restoration field experiment: this consists on the field establishment of native herbaceous species by bioaugmentation with \u0093core microbiome\u0094 from root-zone mine tailings and root-zone soil on incipient technosols produced by the addition of organic-mineral amendments on mine tailings. These phases are designed to be performed in three years.\r\nThis study can provide insights of the promotion of ecological process and natural resilience on microbial communities of mine tailings and surroundings, which can allow the initial plant establishment a development for later possible plant recruitment from the native sclerophyllous forest. This would also evaluate whether mine tailings can be in situ managed instead of been totally removed, which implies high costs and workflow to enterprises. Additionally, this study would represent the first approach of the evaluation of the biological functioning and composition of microbial communities from root-zone mine tailings in Chile, from its current state to the subsequent restoration process.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2021 - Febrero 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25972\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Characterization of the resistance of indicator bacteria against critical antimicrobials and identification of associated risk factors in healthy dogs from the Metropolitan Region\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25972\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25972\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2021 - Abril 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25991\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Effects of eccentric, concentric and eccentric\/concentric training on muscle function and mass, functional performance, cardiometabolic health, quality of life and molecular adaptations of skeletal muscle in COPD patients: a multicenter randomized trial\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25991\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25991\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2021 - Marzo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26002\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia Drosophila suzukii: Plaga presente &#8211; Futura convivencia\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26002\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26002\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2021 - Marzo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26197\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Understanding and modeling visual numerosity perception\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26197\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26197\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2021 - Marzo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26343\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia Drosophila suzukii: Plaga presente &#8211; Futura convivencia\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26343\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26343\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2021 - Marzo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26572\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Understanding and modeling visual numerosity perception\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26572\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26572\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2021 - Agosto 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26817\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Riesgo psicosocial y presentismo: un estudio de cohorte en poblaci\u00f3n chilena\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26817\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26817\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26885\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Empaquetamiento tecnol\u00f3gico de producci\u00f3n de nematodos entomopat\u00f3genos locales en medio l\u00edquido\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26885\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26885\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2021 - Diciembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Escuela Universitaria de Enfermer\u00eda y Terapia Ocupacional de Terrassa [EUIT]<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26954\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Significados y usos del cuerpo en estudiantes de ciencias de la salud\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26954\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26954\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El present projecte pret\u00e9n descriure la visi\u00f3 que els futurs professionals de la salut tenen del cos i els usos que li donen per tal d\u0092afavorir la reflexi\u00f3 sobre el seu impacte en atenci\u00f3 a l\u0092usuari (l\u0092aproximaci\u00f3 al cos de l\u0092altre).\r\nCon\u00e8ixer els discursos i les pr\u00e0ctiques realitzades amb el cos dels estudiants de primer curs de ci\u00e8ncies de la salut (ter\u00e0pia ocupacional i infermeria) que expliquem la seva relaci\u00f3 amb el \u0093cos\u0094.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1210841<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2021 - Marzo 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27072\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            UTILIZATION OF PHOTO-FENTON AND ULTRASOUND PROCESSES IN THE DEPURATION OF LANDFILL LEACHATE\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27072\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27072\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The importance of water for life is indisputable. Nevertheless, water quality and availability are affected by\r\nincreases in consumption and climate change. Indeed, several areas of Chile are suffering acute water\r\nscarcity. Consequently, there is a critical need to develop efficient technologies for wastewater recovery.\r\nHowever, considerations must be given to the fact that some wastewaters have toxic recalcitrant pollutants\r\nrequiring complex treatments, such as landfill leachate (LL). The general goal of the project is to evaluate\r\nthe viability of experimentally improving LL quality by conjointly using the solar photo-Fenton process and\r\nultrasound (US), thereby enhancing photocatalysis, ultimately reducing wastewater toxicity.\r\nThe specific goals are to (i) measure the H2O2 and UV irradiation produced by US in LL (laboratory scale);\r\n(ii) evaluate the hydroxyl radicals generated during treatment processes (laboratory scale); (iii) maximize\r\norganic-pollutant removal in LL by defining the optimal operating conditions for the photo-Fenton\/US process\r\n(laboratory scale); (iv) maximize organic-pollutant removal in LL by defining optimal US power\/frequency in\r\nthe sonolytic process (pilot-plant scale); and (v) evaluate toxicity elimination and energy consumption in LL\r\ntreatments with solar-photocatalytic and US processes (laboratory and pilot-plant scales). The proposed\r\ninvestigation will use a scientific methodology, developing reproducible methods to observe the effects of\r\ndiverse parameters, all with a focus on maximizing contaminants removal. To characterize LL, several\r\nparameters will be evaluated, including chemical oxygen demand, biological oxygen demand, total organic\r\ncarbon, total dissolved nitrogen, pH, metals, ammonia, colour, biodegradability, toxicity, total suspended\r\nsolids, conductivity and humic acid.\r\nTo determine the amount of H2O2 generated by US in a simulated LL, a set of experiments will be run\r\nto produce the sonochemical process, applying different US frequencies (100 kHz, 200 kHz and 300 kHz)\r\nand powers (100 W, 170 W and 250 W), thus obtaining the kinetic reaction to H2O2 production. The\r\namount of UV irradiation formed due to sonoluminescence will be quantified in the same beaker in\r\nthe simulated LL. Sonoluminescence intensity during the runs will be measured using a spectro-radiometer.\r\nTo evaluate the hydroxyl radicals (\u00b7OH) generated in the simulated LL during treatment processes,\r\na method based on the oxidation of 2-proponol will be used. To determine the optimal operating\r\nconditions for the photo-Fenton\/US process to maximize the removal of organic pollutants\r\npresent in the simulated LL, a set of experiments will be carried out in the same photoreactor (1 L),\r\napplying different reagent concentrations, treatment times, and pH levels. To establish optimal US power\r\nand frequency in the sonolytic process to maximize the removal of organic pollutants present in\r\na real LL (after its pretreatment), a set of runs will be carried out at pilot-plant scale in a solar\r\nphotoreactor compound parabolic concentrator (CPC; 12 L useful volume). To evaluate toxicity\r\nelimination from the real LL an Aliivibrio fischeri test, respirometer assay, and phytotoxicity assay will be\r\nused, followed by determining median effective concentrations (EC50) according to the Probit model. Since a\r\nmain disadvantage of the proposed treatments is high-energy consumption, specific energy consumption\r\n(SEC) and electrical energy per order (EEO) will be determined for all processes. All experiments will be done\r\nin triplicate, and filtration and coagulation\/flocculation processes as a pretreatment will be used prior to all\r\nruns. The expected results of the proposed project are to (i) obtain new knowledge related to joint photo-\r\nFenton and ultrasound wastewater treatments, (ii) demonstrate treatment synergies, and (iii) validate the\r\nuse of advanced oxidation processes for improving LL. Project results will be reported in papers, through\r\nthesis work, and at scientific congresses, strengthening national and international research networks.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ANID\/FONDECYT\/1210331<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2021 - Marzo 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27118\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            \u00bfCiudadan\u00edas extractivas? Pr\u00e1cticas ciudadanas en territorios rurales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27118\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27118\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Esta investigaci\u00f3n se propone explorar el concepto de ciudadan\u00eda extractiva para comprender c\u00f3mo la\r\nreconfiguraci\u00f3n de los espacios pol\u00edticos y nuevas formas de ciudadan\u00eda desde lo rural incide en las\r\ndin\u00e1micas entre empresas, Estado y comunidades rurales. Nuestra pregunta de investigaci\u00f3n es \u00bfc\u00f3mo\r\nincide la frontera de recursos en la ciudadan\u00eda extractiva observable en territorios rurales de Chile? En ese\r\nsentido, se sit\u00faa en la intersecci\u00f3n en la geograf\u00eda cr\u00edtica y los estudios agrarios cr\u00edticos para analizar la\r\nagencia de habitantes rurales en la reconfiguraci\u00f3n espacio-temporal de los reg\u00edmenes de control de\r\nrecursos naturales en espacios rurales a partir de la localizaci\u00f3n de cadenas globales de valor. As\u00ed, busca\r\ncontribuir a la geograf\u00eda chilena con sustento emp\u00edrico a nuevas entradas conceptuales, para revitalizar\r\nel debate sobre ruralidad en territorios globalizados. La hip\u00f3tesis que exploraremos en el trabajo de\r\ncampo postula que las fronteras de recursos inciden en tres dimensiones de la experiencia territorial rural\r\n\u0096gobernanza, anclaje y simb\u00f3lica\u0096, lo que lleva a los habitantes sujetos rurales a reformular sus pr\u00e1cticas\r\npol\u00edticas en t\u00e9rminos de argumentaci\u00f3n, participaci\u00f3n, movilizaci\u00f3n y legitimaci\u00f3n, y que desde ellas y en\r\nconjunto configuran ciudadan\u00edas extractivas.\r\n2. OBJETIVOS. Esta investigaci\u00f3n se propone, como objetivo general, caracterizar el v\u00ednculo entre\r\nfronteras de recursos y ciudadan\u00eda extractiva observables en las fronteras de recursos en territorios rurales\r\nen Chile, y como objetivos espec\u00edficos: (1) Caracterizar la configuraci\u00f3n espacial de fronteras de\r\nrecursos de los casos elegidos y el modo en que modifican los mecanismos de acceso y control de la\r\nnaturaleza entre distintos actores; (2) Identificar los espacios y mecanismos de articulaci\u00f3n donde\r\nhabitantes rurales ejercen formas de ciudadan\u00eda extractiva; y (3) Comprender los efectos simb\u00f3licos de la\r\ninteracci\u00f3n entre las cadenas de valor y los habitantes rurales sobre pr\u00e1cticas de ciudadan\u00eda extractiva.\r\n3. METODOLOG\u00cdA. El proyecto se posiciona epistemol\u00f3gicamente desde la geograf\u00eda cr\u00edtica y la ecolog\u00eda\r\npol\u00edtica, lo que implica el uso de t\u00e9cnicas mixtas \u0096cuantitativas, cualitativas y espaciales\u0096 tales como\r\nan\u00e1lisis estad\u00edstico, observaci\u00f3n participante, etnograf\u00eda, entrevistas y cartograf\u00edas participativas. Se ha\r\ndefinido un marco temporal de 30 a\u00f1os (1990-2020), dado que es el periodo de expansi\u00f3n y consolidaci\u00f3n\r\nde la l\u00f3gica de cadenas de valor en los territorios en estudio. Para responder la pregunta de investigaci\u00f3n\r\nse identifica dos tipos distintos de redes globales presentes en territorios rurales de Chile, industria vin\u00edcola\r\ne industria salmonera, en donde se realizar\u00e1 trabajo de campo para obtener evidencia emp\u00edrica que\r\npermita corroborar o refutar la hip\u00f3tesis planteada. Estos dos casos buscan representar diversos tipos de\r\nruralidad e inserci\u00f3n global para identificar una variedad de territorios en Chile. Adem\u00e1s, estos territorios\r\nson representativos de trayectorias diversas de interacci\u00f3n con el Estado y el sistema pol\u00edtico, que van\r\ndesde la radicaci\u00f3n de pioneros promovida mediante incentivos entregados por el Estado en la Patagonia,\r\nal sistema de hacienda y clientelismo marcado por la reforma agraria de la zona central.\r\n4. RESULTADOS ESPERADOS. Desde un punto de vista disciplinar, esperamos comprobar la capacidad\r\nexplicativa del concepto de Ciudadan\u00eda extractiva, para entender las transformaciones rurales derivadas\r\nde la expansi\u00f3n de fronteras de recursos. Ello debiese traducirse en publicaciones cient\u00edficas (al menos 3\r\npublicadas en revistas indexadas disciplinares), formaci\u00f3n de tesistas (4), y actividades y material de\r\ndifusi\u00f3n que fortalezcan el di\u00e1logo con la sociedad civil involucrada.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2021 - Octubre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26061\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Identidad nacional, lectura y sistema escolar\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26061\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26061\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2021 - Abril 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26960\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            \u00bfExcelencia con Inclusi\u00f3n?: Efectos y Estrategias de los Colegios de Alta Exigencia Ante las Nuevas Pol\u00edticas de Admisi\u00f3n\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26960\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26960\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Una estrategia recurrente en la bu&#769;squeda de mejores oportunidades educacionales en Chile ha sido la oferta de una educacio&#769;n selectiva mediante liceos especializados que agrupan estudiantes de alto potencial acade&#769;mico en un mismo establecimiento. En efecto, a los tradicionales liceos emblema&#769;ticos con los que contaba el pai&#769;s, se sumaron 60 \u0093Liceos Bicentenarios\u0094 creados en el primer gobierno del presidente Pin&#771;era a lo largo del pai&#769;s. Para ampliar dicha iniciativa, la actual administracio&#769;n incluye en su programa de gobierno la apertura de 300 nuevos Liceos Bicentenarios durante su periodo de mandato (2018-2022). Sin embargo, esta propuesta plantea que el pai&#769;s no cuenta con evidencia suficiente ni menos concluyente sobre el efecto que tienen los establecimientos de mayor selectividad sobre el desempen&#771;o de sus estudiantes, ni tampoco sobre las pra&#769;cticas pedago&#769;gicas o de gestio&#769;n que explicari&#769;an el valor educacional que agregan, en caso de hacerlo. Este proyecto aspira a llenar ese vaci&#769;o empleando un disen&#771;o metodolo&#769;gico u&#769;nico favorecido por las reglas del nuevo sistema de admisio&#769;n escolar, y por la gradualidad de su implementacio&#769;n, reglas que redefinira&#769;n las poli&#769;ticas de admisio&#769;n que tradicionalmente ha usado este tipo de establecimientos, que tal como lo hace la Ley de Inclusi\u00f3n, denominaremos Establecimientos de Alta Exigencia (EAE). \r\nComo objetivo, los EAE ofreceri&#769;an una educacio&#769;n de alta calidad, orientada al ingreso a la educacio&#769;n superior, empleando exigentes mecanismos de admisio&#769;n que permiten reclutar a estudiantes de alto desempen&#771;o acade&#769;mico. Sin embargo, hasta la fecha, no es claro y es motivo de controversia acade&#769;mica si efectivamente los EAE agregan valor por sus pra&#769;cticas intra-organizacionales, o ma&#769;s bien sus resultados son solo el reflejo de la calidad de su alumnado. El nuevo Sistema de Admisi\u00f3n Escolar (SAE), por su parte, reemplaza el esquema anterior descentralizado y discrecional de admisi\u00f3n adscrito a cada escuela, por un mecanismo centralizado, imparcial y transparente. El SAE asigna estudiantes en base a sus preferencias establecidas en la plataforma de postulaci\u00f3n, y en caso de sobredemanda en una escuela, el sistema aplica criterios de preferencia establecidos por la ley, y en cupos restantes aplica un mecanismo de asignaci\u00f3n aleatorio. La consecuencia de este nuevo sistema sobre los EAE es directa, reconfigura sus poli&#769;ticas de admisio&#769;n y posiblemente su misio&#769;n. En efecto, el SAE reemplazara&#769; progresivamente la admisi\u00f3n de los EAE por rendimiento acad\u00e9mico, por un criterio imparcial a cualquier caracter\u00edstica o desempe\u00f1o previo de los postulantes o sus familias. Ello permitira&#769; por un tiempo acotado la coexistencia de dos sistemas de admisi\u00f3n paralelos, uno selectivo, y otro imparcial. Por tanto, este proyecto dispone de una oportunidad u&#769;nica para tener un contrafactual ma&#769;s fuerte que el resto de los estudios previos, tanto en la literatura nacional como internacional, sobre el efecto de las escuelas selectivas, las trayectorias de estudiantes y la adaptacio&#769;n de sus comunidades escolares a las nuevas regulaciones, y en ello, a la eventual entrada de estudiantes con diferentes caracter\u00edsticas y desempe\u00f1os previos. De ese modo, se espera llenar el vac\u00edo existente sobre el real impacto de los EAE, y a su vez caracterizar los desaf\u00edos de inclusi\u00f3n escolar de los mismos, ante los cambios en la pol\u00edtica de admisi\u00f3n.\r\nEn ese escenario, el presente proyecto emplea una estrategia metodolo&#769;gica mixta, con el propo&#769;sito de estudiar los liceos de excelencia, con foco tanto en el ana&#769;lisis de su impacto sobre las oportunidades educacionales de sus estudiantes, como en el estudio cualitativo de las practicas intra-organizacionales que sostienen dichos resultados. Para ello indagaremos en las respuestas organizacionales y pedago&#769;gicas que supone para los establecimientos combinar un proyecto de excelencia con inclusio&#769;n. Con ese fin analizaremos (i) los efectos de las EAE en los estudiantes postulantes a EAE, admitidos y no admitidos, dada la doble modalidad de admisio&#769;n que co-existiera, comparando sus resultados acade&#769;micos, como aspectos de desarrollo personal y social. A su vez, el proyecto estudiara&#769; (ii) las estrategias de los EAE ante el cambio de sus procesos de admisio&#769;n, especialmente en torno al modo en que enfrentan el desafi&#769;o de re-balancear, combinar y desarrollar un proyecto educativo de excelencia e inclusivo. La estrategia mixta concurrente combinar\u00e1 componentes cuantitativos (ana&#769;lisis bases de datos del nuevo sistema de admisio&#769;n, BBDD Mineduc y SIMCE) con componentes cualitativos (casos de estudios y tipologi&#769;a establecimientos EAE). \r\nLa relevancia radica en su contribuci\u00f3n con mejor evidencia a la disponible a responder la pregunta sobre el aporte de los EAE a las oportunidades educacionales; as\u00ed como a informar al debate pu&#769;blico sobre el impacto de contar o no con EAE, al tratarse de una poli&#769;tica pu&#769;blica atractiva y sensible a los ciclos poli&#769;ticos. Otra razo&#769;n es la evaluacio&#769;n de las poli&#769;ticas de inclusio&#769;n y su grado de viabilidad en ambientes de excelencia, desafi&#769;o importante de un sistema escolar en tra&#769;nsito de des-segregacio&#769;n como el chileno.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2021 - Mayo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26480\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Servicios ecosist\u00e9micos en cuencas con bosques mediterr\u00e1neos andinos y subandinos, bajo un contexto de escasez h\u00eddrica y cambio clim\u00e1tico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26480\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26480\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Los bienes y servicios ecosist\u00e9micos (BSE) del bosque nativo de la zona central de Chile son fundamentales en cuanto a provisi\u00f3n de agua, lo que se ha acentuado frente a la crisis clim\u00e1tica y de escasez h\u00eddrica que afecta a la zona, generando un escenario propicio para la sistematizaci\u00f3n y estructuraci\u00f3n de esquemas de Pago por Servicios Ecosist\u00e9micos (PSE) en cuencas de clima mediterr\u00e1neo en Chile Central. En paralelo y debido a la crisis h\u00eddrica del pa\u00eds acentuada por la Megasequ\u00eda presionada por las proyecciones de cambio clim\u00e1tico, la Direcci\u00f3n General de Aguas (DGA), ha impulsado el desarrollo de \u0093Planes Estrat\u00e9gicos de Gesti\u00f3n H\u00eddrica (PEGH)\u0094 en las 101 cuencas chilenas, de las cuales 10 ya se encuentran en preparaci\u00f3n. Estos planes consideran la implementaci\u00f3n de modelos de balance h\u00eddrico orientados a la simulaci\u00f3n y evaluaci\u00f3n de distintos escenarios tanto clim\u00e1ticos como de gesti\u00f3n del territorio, los que de acuerdo a lo planteado en el presente proyecto se postulan como una herramienta que facilitar\u00eda la cuantificaci\u00f3n de los BSE del bosque nativo y permitir\u00eda apoyar mediante la entrega de informaci\u00f3n relevante, la implementaci\u00f3n de esquemas de PSE sostenibles en el tiempo.\r\n\r\n\r\n\r\nEl clima y la hidrolog\u00eda se rigen por procesos no estacionarios, que var\u00edan en el tiempo y que se afectan por tendencias debido tanto a variabilidad natural como a cambios producto de la actividad humana. De la misma forma, la afectaci\u00f3n y la respuesta de los servicios ecosist\u00e9micos del bosque nativo frente a los cambios hidroclim\u00e1ticos y de gesti\u00f3n local son no estacionarios, por lo que los esquemas de PSE debieran ser flexibles y ajustables a las condiciones cambiantes futuras. En este contexto, el presente proyecto de investigaci\u00f3n se enmarca en la l\u00ednea de investigaci\u00f3n n\u00famero 4 relativa a Provisi\u00f3n de Servicios Ecosist\u00e9micos, que tiene como objetivo el identificar, cuantificar y evaluar la vulnerabilidad y variabilidad a largo plazo de los principales bienes y servicios ecosist\u00e9micos provistos por los bosques mediterr\u00e1neos de Chile Central, usando como caso la cuenca de Aculeo en la Regi\u00f3n Metropolitana. Una vez entendida la relaci\u00f3n de estos servicios ecosist\u00e9micos se evaluar\u00e1n distintos escenarios de intervenci\u00f3n y sus efectos en la provisi\u00f3n bajo condiciones no estacionarias, definidos y priorizados por distintos actores tanto privados como p\u00fablicos, y alimentados por los modelos de balance h\u00eddricos producidos en el marco de los PEGH de la DGA. Este proyecto busca desarrollar estrategias y pol\u00edticas p\u00fablicas en sinergia con otras iniciativas como la de los PEGH, para la mantenci\u00f3n y conservaci\u00f3n de aquellos servicios ecosist\u00e9micos que ser\u00e1n prioritarios bajo las condiciones de mayor incertidumbre frente al cambio clim\u00e1tico. La metodolog\u00eda contempla cuatro aproximaciones: Primero dendrocronolog\u00eda y teledetecci\u00f3n para un an\u00e1lisis del estado de conservaci\u00f3n del bosque. Segundo, simulaci\u00f3n clim\u00e1tica e hidrol\u00f3gica para la vinculaci\u00f3n y evaluaci\u00f3n de la resiliencia de indicadores de estado del bosque con niveles variables de bienes y servicios ecosist\u00e9micos. Tercero, simulaci\u00f3n de escenarios clim\u00e1ticos para explorar la variaci\u00f3n en bienes y servicios ecosist\u00e9micos. Cuarto, mediante trabajo con los actores tanto p\u00fablico como privados, traducci\u00f3n de  los resultados de las proyecciones de las variaciones de los BSE del bosque nativo, en Paquetes de Pago por Servicios Ecosist\u00e9micos y estrategias y pol\u00edticas de conservaci\u00f3n del bosque nativo que consideren la no estacionariedad del clima futuro. Los resultados entregables son: 1) Diagn\u00f3stico de la relaci\u00f3n entre el clima hist\u00f3rico y el bosque nativo, 2) Simulaci\u00f3n de la variaci\u00f3n entre estado del bosque nativo, la hidrolog\u00eda y los bienes y servicios ecosist\u00e9micos, 3) Desarrollo de combinaci\u00f3n de Paquetes de Pago por Servicios Ecosist\u00e9micos para bienes y servicios prioritarios obtenidos a partir de una metodolog\u00eda participativa, incluyendo propuestas de tablas de valores para futuras bonificaciones y memorias de c\u00e1lculo, y 4) Lineamientos de pol\u00edticas y gu\u00eda para sinergia entre iniciativas de conservaci\u00f3n del bosque y\/o ecosistemas de las cuencas.\r\n\r\n\r\n\r\nLa novedad de la propuesta no es solo la inclusi\u00f3n de la incertidumbre clim\u00e1tica como criterio para la selecci\u00f3n de indicadores clave y una propuesta PSE flexible, sino tambi\u00e9n en proponer y demostrar la utilidad de la herramienta de simulaci\u00f3n hidrol\u00f3gica de los PEGH como un elemento clave que puede generar sinergias entre distintas iniciativas a nivel de cuencas que pueden resultar en las bases legales para el Pago por Servicios Ecosist\u00e9micos y la conservaci\u00f3n y restauraci\u00f3n de ecosistemas de bosque nativo como establece la Ley de Bosque Nativo. Finalmente, esta herramienta integrada de calidad del bosque, balance h\u00eddrico y servicios ecosist\u00e9micos, puede derivar en un sistema automatizado de apoyo a las decisiones que permita modificar adem\u00e1s el cambio en las prioridades de los beneficiarios.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1210286<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2021 - Febrero 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26016\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desarrollo de las habilidades matem\u00e1ticas en ni\u00f1os y ni\u00f1as con trastornos de espectro autista.: un compromiso con la equidad educativa en Chile.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26016\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26016\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Aun cuando no hay una cifra oficial que los cuantifique, los ni\u00f1os y ni\u00f1as con Trastornos del Espectro Autista (TEA) constituyen un grupo importante de personas que requieren y demandan formaci\u00f3n escolar, la cual debe ser, naturalmente, de igual calidad que para el resto de los estudiantes. Esta condici\u00f3n neurol\u00f3gica y de desarrollo es reconocida dentro de algunas pol\u00edticas transversales en educaci\u00f3n, como la LGE (Ley 20.370), que declara asegurar la equidad en el sistema educativo, el Decreto 170 para aquello relacionado con el proceso de identificaci\u00f3n y asignaci\u00f3n de recursos del estado para estudiantes con Necesidades Educativas Especiales, el Decreto 83 referido a las adecuaciones curriculares, y el Dise\u00f1o Universal del Aprendizaje (DUA), que propende al desarrollo curricular atendiendo pr\u00e1cticas inclusivas. Adicionalmente, el Ministerio de Educaci\u00f3n ha implementado una serie de manuales y lineamientos espec\u00edficos sobre TEA, tanto para padres y madres, como para educadores y educadoras. A pesar de todo lo anterior, los testimonios y opiniones de las agrupaciones dan cuenta que, para efectos pr\u00e1cticos, a\u00fan hay escasos avances en esta integraci\u00f3n, la cual se ve complicada adem\u00e1s por una serie de estereotipos sociales propios del desconocimiento sobre este trastorno, que asume una capacidad matem\u00e1tica superior a priori, y otros mitos que afectan la convivencia e integraci\u00f3n de estos ni\u00f1os y ni\u00f1as en las comunidades educativas. Dentro de lo espec\u00edficamente relacionado con la Matem\u00e1tica, dentro de los principales problemas para el trabajo matem\u00e1tico con ni\u00f1os y ni\u00f1as con TEA est\u00e1 el aspecto de la comunicaci\u00f3n verbal, adem\u00e1s del d\u00e9ficit observado en funciones ejecutivas, las que pueden manifestarse a trav\u00e9s de problemas de memoria y\/o planificaci\u00f3n\/organizaci\u00f3n, memoria de trabajo, flexibilidad mental, atenci\u00f3n y autocontrol. As\u00ed, el presente proyecto apunta como objetivo, el fortalecimiento de las habilidades matem\u00e1ticas de ni\u00f1os y ni\u00f1as con TEA. El dise\u00f1o ser\u00e1 realizado bajo un enfoque preferentemente cuantitativo, orientado al nivel preescolar y primer ciclo b\u00e1sico.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2021 - Diciembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26025\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Conocimiento matem\u00e1tico, creencias y emociones hacia la matem\u00e1tica, y desempe\u00f1o acad\u00e9mico en el \u00e1mbito de la matem\u00e1tica en la formaci\u00f3n en Pedagog\u00eda en Educaci\u00f3n B\u00e1sica y Pedagog\u00eda en Educaci\u00f3n Especial\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26025\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26025\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26048\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            La tecnolog\u00eda NIR como herramienta de apoyo a la investigaci\u00f3n agr\u00edcola y pecuaria\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26048\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26048\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26049\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            XIII Concurso de Proyectos de Diplomado Regional en Temas de Ciencia, Tecnolog\u00eda e Innovaci\u00f3n\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26049\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26049\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Diplomado gesti\u00f3n sostenible de sistemas pecuarios[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2021 - Diciembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26195\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Conocimiento matem\u00e1tico, creencias y emociones hacia la matem\u00e1tica, y desempe\u00f1o acad\u00e9mico en el \u00e1mbito de la matem\u00e1tica en la formaci\u00f3n en Pedagog\u00eda en Educaci\u00f3n B\u00e1sica y Pedagog\u00eda en Educaci\u00f3n Especial\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26195\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26195\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26281\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Incrementar la eficiencia de riego por surcos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26281\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26281\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2021 - Febrero 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26335\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Electrostatically\u0096induced granular clustering by tribocharging\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26335\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26335\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Far from simple steric repulsion, i.e., volumetric repulsion, the dynamics of granular systems are driven by a menagerie of interactions: dissipative collisions, van der Waals forces, electrostatic Coulomb and polarization forces, viscous drag and, in the presence of even minute amounts of liquid, capillary bridges or ice coatings. Despite its importance and the development of many powerful experimental, numerical and theoretical tools, until now, a unified description of granular media is lacking, even for the simplest model situation of perfectly spherical, impenetrable and dissipative particles.\r\nOne of the most important topics in granular media research is clustering, for both fundamental and applied reasons. Clustering produces large gradients, which makes usual gradient perturbations schemes more difficult, which even poses questions about the validity of continuum approaches for these systems. Clustering and coarsening are also relevant for many industrial applications, including grain and powder storage, transport and manipulation, in the food, mining and chemical industries, to mention a few.\r\nElectrostatically\u0096induced granular clustering has emerged as a mechanism with fundamental and practical implications. The electrification of such systems occurs through tribocharging\u0097the exchange of charge between contacting surfaces. Despite its importance, how insulators transfer such large amounts of charge during contact is not well-understood. How this can also occur for identical materials during contact is puzzling as well. Furthermore, the nature of the charge carrier is also not settled. Concerning applications, just recently electrostatically\u0096induced granular clustering has been revealed as a possible enhancing mechanism for granular coarsening in a very important and unsolved issue: the formation of planetesimals, which can be considered as baby planets (from 1 km size it is expected that gravity should be the driving accretion force). Indeed, despite clear evidence, our current theoretical understanding is that rocky planets should not exist; a basic ingredient seems to be missing for explaining the clustering of grains in the sub- mm to cm range. We propose that electrification through tribocharging is the missing ingredient.\r\nThus, the main objective of this proposal is to address how different pair-wise interactions and, in general, particle and collisional properties, lead to sustained cluster growth. We are developing two experimental systems to make concrete steps toward this goal. In the first, we are using a free-fall apparatus to observe collisions between sub-mm particles in vacuum and zero-gravity conditions. In the second, we are forging into the new territory of interactions between millimeter-scale particles or clusters with a controlled acoustic levitation setup. In order to understand the microphysics of grain growth in the sub-mm to cm range, our immediate objective is to characterize the sticking efficiencies and dominant forces\u0097including the possibility of same-material tribocharging\u0097in a variety of conditions. In the first experimental setup, we will focus on few-particle interactions and clustering. In the second, we will study controlled collisions between a few up to many-particle clusters. Working on these two experiments in tandem will enable us to characterize collisions over decades of data in cluster size and impact energy, and quantify same-material tribocharging. For both experiments we will use standard dielectric materials (as ZrO2:SiO2 composites) as a benchmark. Then, we will use analog meteorite materials (e.g. San Carlos Olivine) in both setups, and original meteorite grains (Allende meteorite) with the ultrasonic setup, where controlled collisions can be done for smaller amounts of material. The outcome of such experiments will be a phase portrait of collisional aggregation efficiency covering features ranging from particle and cluster size to particle interactions, particle composition and impact energy. One particular contribution we will focus on is the effect of tribocharging on the formation efficiency of larger clusters, which should be relevant toward our current understanding of asteroid and planetesimal formation.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26448\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Hydroclima y Recursos H\u00eddricos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26448\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26448\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2021 - Noviembre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26764\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26764\" aria-expanded=\"false\" aria-controls=\"collapse-26764\">\n                                            Estudio Longitudinal Social de Chile (ELSOC)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26764\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26764\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El Estudio Longitudinal Social de Chile (ELSOC) es un estudio \u00fanico en Chile y Am\u00e9rica Latina, el cual encuesta anualmente a una muestra representativa de la poblaci\u00f3n urbana en Chile a lo largo de una d\u00e9cada, con el fin de evaluar la manera c\u00f3mo piensan, sienten y se comportan los chilenos en torno a un conjunto de temas referidos al conflicto y la cohesi\u00f3n social en el pa\u00eds.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1210286<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2021 - Febrero 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26811\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desarrollo de las habilidades matem\u00e1ticas en ni\u00f1os y ni\u00f1as con trastornos de espectro autista.: un compromiso con la equidad educativa en Chile.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26811\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26811\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Aun cuando no hay una cifra oficial que los cuantifique, los ni\u00f1os y ni\u00f1as con Trastornos del Espectro Autista (TEA) constituyen un grupo importante de personas que requieren y demandan formaci\u00f3n escolar, la cual debe ser, naturalmente, de igual calidad que para el resto de los estudiantes. Esta condici\u00f3n neurol\u00f3gica y de desarrollo es reconocida dentro de algunas pol\u00edticas transversales en educaci\u00f3n, como la LGE (Ley 20.370), que declara asegurar la equidad en el sistema educativo, el Decreto 170 para aquello relacionado con el proceso de identificaci\u00f3n y asignaci\u00f3n de recursos del estado para estudiantes con Necesidades Educativas Especiales, el Decreto 83 referido a las adecuaciones curriculares, y el Dise\u00f1o Universal del Aprendizaje (DUA), que propende al desarrollo curricular atendiendo pr\u00e1cticas inclusivas. Adicionalmente, el Ministerio de Educaci\u00f3n ha implementado una serie de manuales y lineamientos espec\u00edficos sobre TEA, tanto para padres y madres, como para educadores y educadoras. A pesar de todo lo anterior, los testimonios y opiniones de las agrupaciones dan cuenta que, para efectos pr\u00e1cticos, a\u00fan hay escasos avances en esta integraci\u00f3n, la cual se ve complicada adem\u00e1s por una serie de estereotipos sociales propios del desconocimiento sobre este trastorno, que asume una capacidad matem\u00e1tica superior a priori, y otros mitos que afectan la convivencia e integraci\u00f3n de estos ni\u00f1os y ni\u00f1as en las comunidades educativas. Dentro de lo espec\u00edficamente relacionado con la Matem\u00e1tica, dentro de los principales problemas para el trabajo matem\u00e1tico con ni\u00f1os y ni\u00f1as con TEA est\u00e1 el aspecto de la comunicaci\u00f3n verbal, adem\u00e1s del d\u00e9ficit observado en funciones ejecutivas, las que pueden manifestarse a trav\u00e9s de problemas de memoria y\/o planificaci\u00f3n\/organizaci\u00f3n, memoria de trabajo, flexibilidad mental, atenci\u00f3n y autocontrol. As\u00ed, el presente proyecto apunta como objetivo, el fortalecimiento de las habilidades matem\u00e1ticas de ni\u00f1os y ni\u00f1as con TEA. El dise\u00f1o ser\u00e1 realizado bajo un enfoque preferentemente cuantitativo, orientado al nivel preescolar y primer ciclo b\u00e1sico.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2021 - Diciembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26968\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Conocimiento matem\u00e1tico, creencias y emociones hacia la matem\u00e1tica, y desempe\u00f1o acad\u00e9mico en el \u00e1mbito de la matem\u00e1tica en la formaci\u00f3n en Pedagog\u00eda en Educaci\u00f3n B\u00e1sica y Pedagog\u00eda en Educaci\u00f3n Especial\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26968\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26968\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2021 - Marzo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad del Desarrollo<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26971\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            La construcci\u00f3n del pensamiento algebraico en la Formaci\u00f3n Inicial Docente: Un estudio exploratorio\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26971\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26971\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Hist\u00f3ricamente, el \u00e1lgebra escolar ha estado vinculado al uso exclusivo de letras y s\u00edmbolos matem\u00e1ticos, lo cual es una mirada muy reducida sobre lo que realmente significa el \u00e1lgebra en la escuela. En los \u00faltimos a\u00f1os, diferentes iniciativas promueven el desarrollo del pensamiento algebraico en la educaci\u00f3n b\u00e1sica, tipo de pensamiento matem\u00e1tico que supone prestar la atenci\u00f3n a las relaciones que escolares construyen, m\u00e1s que a procedimientos aislados. A pesar de los esfuerzos por incorporar el pensamiento algebraico desde los primeros cursos, todav\u00eda existen profesores que creen que el \u00e1lgebra es el conocimiento de procedimientos mec\u00e1nicos que involucran el uso de letras y s\u00edmbolos matem\u00e1ticos y, por tanto, sus esfuerzos apuntan a ese prop\u00f3sito. Lo anterior cobra fuerza en el contexto de la Formaci\u00f3n Inicial Docente por dos razones principales: (a) los conocimientos algebraicos de los futuros profesores chilenos al terminar su formaci\u00f3n son preocupantes (Santiago et al., 2013); y (b) el pensamiento algebraico es uno de los focos centrales del curr\u00edculo matem\u00e1tico nacional (Mineduc, 2012). A partir de lo anterior, surge la necesidad de identificar y comprender c\u00f3mo se desarrolla el conocimiento profesional sobre \u00e1lgebra que tienen los futuros profesores de educaci\u00f3n b\u00e1sica.\r\nEste proyecto adopta la idea que el \u00e1lgebra y el pensamiento algebraico van m\u00e1s all\u00e1 del uso de la notaci\u00f3n algebraica; se favorece el uso de representaciones tan variadas como el lenguaje natural, representaciones manipulativas, pict\u00f3ricas, num\u00e9ricas, tabulares, gr\u00e1ficas, entre otras. En concreto, seguimos el marco conceptual propuesto por Kaput (2008) sobre su forma de entender el \u00e1lgebra y el pensamiento algebraico: la generalizaci\u00f3n y su representaci\u00f3n constituyen aspectos centrales. Dado que este proyecto se interesa por el conocimiento profesional de los futuros profesores, nos centramos en el la competencia denominada Mirada Profesional (Jacobs et al., 2010), la cual busca reconocer y dar sentido a lo hechos que suceden en la clase de matem\u00e1ticas para poder explicar e informar el aprendizaje de las matem\u00e1ticas, lo que apoyar\u00e1 las decisiones que tomen los futuros profesores con el prop\u00f3sito de favorecer el aprendizaje de sus estudiantes. Espec\u00edficamente, la Mirada Profesional involucra tres habilidades interrelacionadas: (a) prestar atenci\u00f3n a las estrategias de los ni\u00f1os; (b) interpretar las comprensiones de los ni\u00f1os; y (c) decidir c\u00f3mo responder sobre la base de las comprensiones de los ni\u00f1os (toma de decisiones).\r\nEn t\u00e9rminos metodol\u00f3gicos, este proyecto sigue las directrices de la Investigaci\u00f3n de Dise\u00f1o (Cobb, Confrey, diSessa, Lehrer y Schauble, 2003). Concretamente, esta investigaci\u00f3n se llevar\u00e1 a cabo a trav\u00e9s de un experimento de ense\u00f1anza, el cual estudia la naturaleza del desarrollo de ideas, herramientas o modelos en los que est\u00e1n contenidos futuros profesores; y entrevistas individuales semiestructuradas, las cuales permitir\u00e1n profundizar con mayor detalle en los conocimientos de los futuros profesores. En cuanto a los participantes, esta investigaci\u00f3n contar\u00e1 con la colaboraci\u00f3n de los futuros profesores matriculados en la c\u00e1tedra \u0093Ense\u00f1anza del \u00c1lgebra, Datos y Azar\u0094 de la carrera de Pedagog\u00eda en Educaci\u00f3n B\u00e1sica con menci\u00f3n en Ingl\u00e9s de la UDD. Este curso es obligatorio y se imparte en el sexto semestre. En lo que respecta al dise\u00f1o del proyecto, los futuros profesores participar\u00e1n de 8 sesiones de clases destinadas a la ense\u00f1anza y aprendizaje del \u00e1lgebra, donde se trabajar\u00e1n los diferentes contenidos algebraicos del modelo conceptual seguido, as\u00ed como las habilidades propias de la Mirada Profesional. Posteriormente, se observar\u00e1 a un grupo de estos futuros profesores en su Pr\u00e1ctica y Seminario III, donde estos podr\u00e1n conducir secuencias de ense\u00f1anza y aprendizaje referidas al \u00e1lgebra. El foco de an\u00e1lisis de la informaci\u00f3n estar\u00e1 centrado en las respuestas y producciones (escritas y orales) de los futuros profesores, mediante un an\u00e1lisis de las clases grabadas.\r\n\tEl impacto esperado de los resultados influir\u00e1 en tres \u00e1reas principales: (a) investigaci\u00f3n e internacionalizaci\u00f3n, consolidando y posicionando una l\u00ednea de investigaci\u00f3n novedosa en el campo de la Educaci\u00f3n Matem\u00e1tica; (b) docencia, enriqueciendo la Formaci\u00f3n Inicial Docente, a trav\u00e9s del desarrollo y promoci\u00f3n del pensamiento algebraico en sus estudiantes; y (c) redes de colaboraci\u00f3n, lo cual permitir\u00e1 conectar y posicionar a esta investigaci\u00f3n con un conjunto de investigadores internacionales que asesoran y avalan la calidad y relevancia de este proyecto de investigaci\u00f3n.\r\n\r\nReferencias\r\nCobb, P., Confrey, J., diSessa, A., Lehrer, R. y Schauble, L. (2003). Design experiments in educational research. Educational Researcher, 32(1), 9-13.\r\nJacobs, V. R., Lamb, L. L. y Philipp, R. (2010). Professional noticing of children\u0092s mathematical thinking. Journal for Research in Mathematics Education, 41(2), 169-202.\r\nKaput, J. (2008). What is algebra? What is the algebraic reasoning? En J. J. Kaput, D. W. Carraher y M. L. Blanton (Eds.), Algebra in the early grades (pp. 5-17). Nueva York, NY: Lawrence Erlbaum Associates.\r\nMinisterio de Educaci\u00f3n de Chile [MINEDUC] (2012). Bases Curriculares. Primero a Sexto B\u00e1sico. Santiago, Chile: Autor.\r\nSantiago, P., Benavides, F., Danielson, C., Goe, L. y Nusche, D. (2013). Teacher Evaluation in Chile. Par\u00eds: OCDE.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 591123<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2021 - Octubre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>FONDART<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27106\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27106\" aria-expanded=\"false\" aria-controls=\"collapse-27106\">\n                                            FONDART Regional \u0093Retratos del v\u00ednculo materno\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27106\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27106\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Artista Responsable, FONDART Regional 591123, \u0093Retratos del v\u00ednculo materno\u0094 - Proyecto de creaci\u00f3n art\u00edstica con madres en la regi\u00f3n de Los Lagos, marzo 2021 a octubre de 2022. Monto $ 6.392.944[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> EQUR19003<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26624\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            UHPLC-DAD\/RID\/DRF para el potenciamiento de la investigaci\u00f3n transdisciplinaria aplicada al mejoramiento gen\u00e9tico de frutales y hortalizas y a la caracterizaci\u00f3n de su calidad funcional y nutricional\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26624\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26624\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El cromat\u00f3grafo permite evaluar aspectos tan importantes como la calidad de la fruta, cantidad y tipos de az\u00facares que tiene, o algunos compuestos nutricionales que puedan ser de valor en la investigaci\u00f3n y en la valorizaci\u00f3n de los productos agr\u00edcolas[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2021 - Septiembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26196\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Investigaci\u00f3n de la estructura sem\u00e1ntica asociada al estereotipo g\u00e9nero-ciencias\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26196\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26196\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad del Desarrollo<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26972\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Summer School 2021: \u00c1lgebra m\u00e1s all\u00e1 de letras y n\u00fameros\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26972\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26972\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El prop\u00f3sito general de la investigaci\u00f3n es estudiar la capacidad de generalizaci\u00f3n evidenciada por estudiantes de 10-11 a\u00f1os al trabajar con diferentes contenidos de car\u00e1cter algebraico. La relevancia e impacto de este proyecto tiene relaci\u00f3n con el t\u00f3pico que aborda: la generalizaci\u00f3n, un t\u00f3pico que se reconoce como la esencia de actividad matem\u00e1tica, la cual permite a los estudiantes hacer expl\u00edcito este tipo de pensamiento (Carpenter y Franke, 2001; Dienes, 1961; Dreyfus, 2002; Krutetskii, 1976; Lee, 1996; Mason, 1996). Si bien estudios previos muestran c\u00f3mo estudiantes de 6-12 a\u00f1os generalizan y expresan dichas relaciones al responder a diferentes problemas y situaciones de car\u00e1cter algebraico (e.g., Ayala-Altamirano y Molina, 2019; Blanton y Kaput, 2004; Brizuela, Blanton, Sawrey, Newman-Owens y Murphy Gardiner, 2015; Morales, Ca\u00f1adas, Brizuela y G\u00f3mez, 2018; Rivera y Becker, 2008; Schliemann, Carraher y Brizuela, 2012; Warren, Miller y Cooper, 2013), y aunque el \u00e1lgebra se ha incorporado en curr\u00edculo nacional, existe poca evidencia sobre c\u00f3mo se est\u00e1 desarrollando est\u00e1 capacidad en los estudiantes chilenos. Con base en la idea anterior, la conjetura general es que estos estudiantes tambi\u00e9n mostrar\u00e1n evidencias de generalizaci\u00f3n a partir de actividades propuestas. En concreto, la conjetura es que luego de sucesivas intervenciones en el aula, los estudiantes generalizar\u00e1n las relaciones matem\u00e1ticas involucradas en diferentes problemas, mediante una sofisticaci\u00f3n en la forma de: (a) expresar y representar dichas generalizaciones; (b) justificar y argumentar sus ideas; y (c) razonar. A partir de lo anterior, y considerando las caracter\u00edsticas propias del dise\u00f1o y el contexto en el cual se llevar\u00e1 a cabo este estudio, la pregunta de investigaci\u00f3n es \u00bfc\u00f3mo generalizan estudiantes de 10-11 a\u00f1os al participar de diferentes actividades que tienen un car\u00e1cter algebraico? Para responder a esta pregunta, se han definido tres objetivos de investigaci\u00f3n (O):\r\nO.1. Describir y caracterizar las representaciones usadas por estudiantes de 10-11 a\u00f1os al generalizar las relaciones matem\u00e1ticas involucradas en diferentes problemas de car\u00e1cter algebraico (aritm\u00e9tica generalizada; equivalencia, expresiones, ecuaciones e inecuaciones; y pensamiento funcional).\r\nO.2. Analizar las justificaciones matem\u00e1ticas evidenciadas por estudiantes de 10-11 a\u00f1os al generalizar las relaciones matem\u00e1ticas involucradas en diferentes problemas de car\u00e1cter algebraico (aritm\u00e9tica generalizada; equivalencia, expresiones, ecuaciones e inecuaciones; y pensamiento funcional).\r\nO.3. Identificar evidencias en el razonamiento matem\u00e1tico de los estudiantes de 10-11 a\u00f1os al generalizar las relaciones matem\u00e1ticas involucradas en diferentes problemas de car\u00e1cter algebraico (aritm\u00e9tica generalizada; equivalencia, expresiones, ecuaciones e inecuaciones; y pensamiento funcional).[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2021 - Diciembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26088\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia y adopci\u00f3n de Tecnolog\u00edas para la Gesti\u00f3n de Riesgo en el Proceso Productivo de la Cereza: hacia una agricultura de precisi\u00f3n para la Regi\u00f3n de O\u0092Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26088\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26088\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Transferencia y adopci\u00f3n de Tecnolog\u00edas para la Gesti\u00f3n de Riesgo en el Proceso Productivo de la Cereza: hacia una agricultura de precisi\u00f3n para la Regi\u00f3n de O\u0092Higgins[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2021 - Marzo 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26175\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            TRANSPORT -Experimental and Modeling- of antimicrobials in soils\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26175\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26175\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"].[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> PID2020-116346GB-I00<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2021 - Agosto 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Ciencia e Innovaci\u00f3n, Gobierno de Espa\u00f1a<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26735\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Advancing computational intelligence wearable multisensor signal processing techniques for biomedical, neuroscience and robotic interaction applicationsAvances en t\u00e9cnicas de inteligencia computacional para el proceso de sensores m\u00faltiples portables para\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26735\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26735\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Data driven computational intelligence (CI) techniques have gained a principal role in the analysis and interpretation of sensor signals such\r\nas optical cameras, LiDAR, wearable inertial sensors, wearable physiological sensors including electroencephalographic (EEG) recorders,\r\nand a wide variety of medical imaging devices. Currently, deep learning approaches are the artificial intelligence (AI) mainstream providing\r\nsolutions to the entire spectrum of AI problems. We are specifically interested in developments related to deep reinforcement learning for\r\ndecision making and control, and generative adversarial networks, graph neural networks, and semantic deep networks as promising\r\nparadigms for the analysis and interpretation of synchronized multisensor signals that arise in the focus domain of application, which is the\r\ncorrelated analysis and interpretation of the neural activity and the behavioral observation of humans and animal models. A field that could\r\nbe identified as computational neuroethology. In short we aim to measure quantitatively the body motion to assess the external behavioral\r\ntraits, in synchrony with the neural activity measurement. We benefit from recent developments wearable wireless connected electroencephalograms (EEG), and Inertial measurement systems (IMS), as well as accurate close range\r\nLiDAR cameras. The project will be devoted to the development of technological solutions for the realization of experimental\r\nmeasurements, and deep learning based computational tools for data analysis. We will collaborate with working team members in the\r\ndesign and construction of experimental arenas.\r\nAdvanced computational methods will be applied to data analysis obtained from animal models which have been developed by the\r\nscientific community to assess quantitatively the effect of drugs or cognitive experiments. Actual experimental work is envisaged to be\r\ncarried out (or has already been carried out) by external collaborators under the supervision of corresponding ethical committees. Animal\r\nmodel data will be provided by MI Carre\u00f1o from University of Montreal, U Liberal of the UPV\/EHU, R Angulo from Universidad\r\nOHiggings (Chile).\r\nWe will develop human neuroethological prototypes that can be applied to aid the refined and differential diagnosis of some behavioral\r\nsyndromes, such as the autistic spectrum condition, some neurodegenerative conditions (Alzheimers disease, Parkinsons Disease), and\r\nthe aging process in general. In the current COVID-19 pandemic this approach would be helpful to assess the behavioral impact of the\r\nneural damages that the coronavirus appears to inflict to some subjects.\r\nFurthermore, we will explore neuro-ethologically enhanced human-robot interaction, where the robotic counterpart will take into account\r\nbehavioral and neural cues to modulate the interaction in order to minimize stress and maximize safety. We will collaborate with A Lekova\r\nof IR-BAS Bulgaria on the impact of robot interaction with children with communication disorders. Works on human-robot interaction will\r\nbe inspired by T Hashimoto (JAIST) and H Wagatsuma (Kyutech) from Japan.\r\nFinally, we will consider the neuroethological observation of human social interactions in unstructured environments and mediated by\r\ngame playing. This tool will be help in the analysis of increasingly prevalent social behavior disorders.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 19-CTIGH-121324-03<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Corporaci\u00f3n de Fomento de la Producci\u00f3n - CORFO<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26934\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Modelo de balance h\u00eddrico en acu\u00edfero de roca fracturada\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26934\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26934\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo general: sesarrollar un modelo de balance h\u00eddrico en acu\u00edfero de roca fracturada. Objetivos espec\u00edficos: (i) identificar un sitio piloto de roca fracturada; (ii) instrumentar el piloto para monitorear los flujos h\u00eddricos; (iii) dise\u00f1ar e implementar la metodolog\u00eda de balance h\u00eddrico en acu\u00edferos de roca fracturada.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FON1900022<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2020 - Octubre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26039\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Escolarizaci\u00f3n de las pr\u00e1cticas pedag\u00f3gicas de educadoras de p\u00e1rvulos de Segundo Nivel de Transici\u00f3n. Evidencia para Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26039\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26039\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto busca generar evidencia para Chile sobre la escolarizaci\u00f3n de la educaci\u00f3n parvularia. \u00c9sta es una tendencia mundial que la OCDE ha definido como la adopci\u00f3n de enfoques y contenidos propios de la educaci\u00f3n b\u00e1sica (OECD, 2001, p. 129), por ejemplo, la reducci\u00f3n de las oportunidades de juego (limit\u00e1ndolo al tiempo del recreo), y el foco en el desarrollo de habilidades cognitivas (en desmedro, por ejemplo, de la creatividad). Principalmente observada en grupos de 4 y 5 a\u00f1os de edad, la escolarizaci\u00f3n de la educaci\u00f3n parvularia ha sido interpretada como una visi\u00f3n estrecha de la preparaci\u00f3n para la escuela, (OECD 2006, p. 42, 219).\r\nEn Chile las autoridades educacionales han manifestado su preocupaci\u00f3n por esta tendencia (Ministerio de Educaci\u00f3n, 2016, p. 19; MINEDUC, 2018, p. 26). Adem\u00e1s, varios estudios han evidenciado elementos de escolarizaci\u00f3n en establecimientos de todas las dependencias para Niveles Medios y Transici\u00f3n (Pardo & Woodrow 2014; Pardo & Opazo 2019; Santib\u00e1\u00f1ez et al. 2009; Grau et al. 2018; Grau et al. 2018; Strasser et al. 2009; S\u00e1nchez & G\u00f3mez 2010).\r\nOBJETIVO GENERAL DEL PROYECTO: Explorar la presencia de elementos de escolarizaci\u00f3n en aulas de Segundo Nivel de Transici\u00f3n (NT2) en establecimientos municipales y particular subvencionados de la Regi\u00f3n Metropolitana y de la Regi\u00f3n de O\u0092Higgins.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2020 - Marzo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25973\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Generaci\u00f3n de capital social entre los productores ap\u00edcolas y la universidad de O\u0092Higgins, para mejorar el estatus sanitario y epidemiol\u00f3gico de las colmenas de la regi\u00f3n de O\u0092Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25973\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25973\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetivo es dise\u00f1ar e implementar una estrategia transdisciplinaria de vinculaci\u00f3n entre los apicultores de la regi\u00f3n y la Universidad de O'Higgins, que permita construir una \u0093Hoja de Ruta\u0094 para resolver las brechas existentes en el sector y definir las l\u00edneas de investigaci\u00f3n aplicada a desarrollarse. Esto permitir\u00e1 mejorar la asociatividad de los apicultores, mejorar la salud de las colmenas, los servicios de polinizaci\u00f3n y por ende la productividad ap\u00edcola regional.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2020 - Marzo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26420\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Generaci\u00f3n de capital social entre los productores ap\u00edcolas y la universidad de O\u0092Higgins, para mejorar el estatus sanitario y epidemiol\u00f3gico de las colmenas de la regi\u00f3n de O\u0092Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26420\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26420\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetivo es dise\u00f1ar e implementar una estrategia transdisciplinaria de vinculaci\u00f3n entre los apicultores de la regi\u00f3n y la Universidad de O'Higgins, que permita construir una \u0093Hoja de Ruta\u0094 para resolver las brechas existentes en el sector y definir las l\u00edneas de investigaci\u00f3n aplicada a desarrollarse. Esto permitir\u00e1 mejorar la asociatividad de los apicultores, mejorar la salud de las colmenas, los servicios de polinizaci\u00f3n y por ende la productividad ap\u00edcola regional.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26625\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Liofilizador Labconco para el procesamiento de muestras de origen animal y vegetal\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26625\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26625\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2020 - Diciembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26330\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Blood-Brain Barrier  Programming Dysfunction in Intrauterine Hypoxia: Epigenetics, Permeability and Integrity Assessment for Cerebrovascular Protection\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26330\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26330\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Goal: This grant aims to describe the role of epigenetics programming in the progression of BBB injury in growth-restricted neonates. Furthermore, we will identify the molecules and mechanisms of junctional complexes and adhesion molecules of the BBB that are affected by gestational hypoxia.\r\n\r\nThe original contribution of this project is to trace the time course of origins and outcomes of the BBB permeability and integrity impairment related to epigenetic mechanisms, due to gestational chronic hypoxia.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1190254<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2020 - Marzo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27094\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desarrollo de interlengua en estudiantes secundarios haitianos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27094\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27094\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"].[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ID 757-69-LE20<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2020 - Mayo 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Salud<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26665\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estudio sobre acceso a informaci\u00f3n de salud mental en la poblaci\u00f3n general\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26665\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26665\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La presente propuesta tiene como objetivo adaptar y validar un instrumento de evaluaci\u00f3n del grado de conocimiento de la poblaci\u00f3n general sobre salud mental y de sus actitudes en torno a la b\u00fasqueda de ayuda, en el marco del concepto de literacidad en salud mental y aplicar este instrumento a una muestra predeterminada que permita generar una l\u00ednea base sobre la cual planificar acciones y evaluar avances en el tiempo. Esto responde a la licitaci\u00f3n p\u00fablica hecha por el Ministerio de Salud de Chile: Estudio sobre acceso a informaci\u00f3n de salud mental en la poblaci\u00f3n general Licitaci\u00f3n ID 757-69-LE20.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ID 757-69-LE20<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2020 - Mayo 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Salud<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26821\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estudio sobre acceso a informaci\u00f3n de salud mental en la poblaci\u00f3n general\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26821\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26821\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La presente propuesta tiene como objetivo adaptar y validar un instrumento de evaluaci\u00f3n del grado de conocimiento de la poblaci\u00f3n general sobre salud mental y de sus actitudes en torno a la b\u00fasqueda de ayuda, en el marco del concepto de literacidad en salud mental y aplicar este instrumento a una muestra predeterminada que permita generar una l\u00ednea base sobre la cual planificar acciones y evaluar avances en el tiempo. Esto responde a la licitaci\u00f3n p\u00fablica hecha por el Ministerio de Salud de Chile: Estudio sobre acceso a informaci\u00f3n de salud mental en la poblaci\u00f3n general Licitaci\u00f3n ID 757-69-LE20.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 2495691<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2020 - Enero 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Forskningsr\u00e5det<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27120\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27120\" aria-expanded=\"false\" aria-controls=\"collapse-27120\">\n                                            Responsible innovation in the Norwegian salmon farming industry: Grand Societal Challenges, Dilemmas and Improvements\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27120\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27120\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Norwegian salmon farming firms are highly influential in the increasingly global salmon farming industry. In 2018, the export value of farmed salmon from Norway totalled 68bn NOK. The project studies dilemmas arising between economic, environmental and social concerns in the salmon farming industry in Norway, Canada, Australia and Chile through mapping the global networks of leading Norwegian salmon farming firms.\r\n\r\nWe intend to study intersections between salmon farming and local\/regional\/national conditions in the involved countries. In so doing we wish to identify tensions between economic, environmental and social dilemmas, and the solutions to these tensions by firms in different geographical locations. Furthering this, the project aims to facilitate co-creation of knowledge between different stakeholders towards improvement of innovation practices and their sustainability (i.e. responsibility) in different contexts. This is done by setting up Responsible Innovation Labs (in Norway and Chile) involving participating researchers, firms, suppliers and customers, NGOs and regulating authorities. Central topics in the Labs will concern how to implement and adapt the UN?s Sustainable Development Goals and linking solutions to context-specific challenges and solutions, aiming to spur responsible innovation practices in the industry.\r\n\r\nThe project is led by prof. Arnt Fl\u00f8ysand, Western Norway University of Applied Sciences. Research partners in the project are University of Stavanger and Pontificia Universidad Catolica de Chile. In addition to a strong team of researchers, several PhD students will be recruited. The project is well-embedded among central partners in the salmon farming industry in Norway, and industry partners, together with other stakeholders from e.g. government, NGOs and regulatory bodies, play important roles in co-creating novel knowledge applicable for theoretical, empirical and practical purposes.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2020 - Octubre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26388\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Peach (Prunus persica) Pathogen Recognizing Receptors (PRR) and their role in pathogen resistance\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26388\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26388\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Crop pests and diseases lead to massive production loss, creating a global food supply and economic loss. Modern agriculture controls diseases by extensive application of chemicals, however this strategy brings undesired effects, such as human health problems by exposure to these chemicals, environmental contamination and development of pesticide resistant pathogens.\r\nAgricultural industry is an economically important activity in Chile, compromising close to 10% of the labor force. The fruit industry (excluding table grapes) corresponds to 8.5% of the arable lands (342,654.2 hectares), where Prunus persica (peach and nectarines, called hereinafter as Peach) has an important place. Peach orchards are affected by several diseases such as, bacterial canker caused by the bacteria Pseudomonas syringae and brown rot blossom blight caused by the fungi Monilinia fructicola and M. laxa, which are controlled mainly by using pesticides. In this context, the need to better understand peach immunity has arisen for developing alternative or supplementary strategies to control crop diseases.\r\nPlant immunity relies on the capacity of each individual cell to recognize pathogen threat, through cell surface and intracellular receptors, initiating immune responses to defend themselves. Cell surface receptors are called Pattern Recognition Receptors (PRRs) by their ability of recognizing characteristic microbial-derived molecules called microbe-associated molecular patterns (MAMPs). Upon MAMP recognition Pattern Triggered Immunity (PTI) is activated, defense responses are elicited enabling the plant to ward off pathogen colonization. MAMPs are distinctive molecules present in bacteria or fungi, non-strain specific, such as bacterial flagellin and fungal endoxylanases, which are recognized by specific PRRs, forming the MAMP\/PRR recognition system that triggers the defense. The presence of PRRs is tightly correlated with higher broad pathogen resistance. In fact, transgenic Citrus sinensis, Medicago truncatula, Triticum avium, Nicotiana benthamiana, and Solanum lycopersicum carrying exogenous PRR present higher pathogen resistance. Moreover, Quantitative Trait Loci (QTL) linking resistance to pathogens with PRRs in Phaseolus vulgaris and Hordeum vulgare. These evidences highlight the potential of exploiting MAMP\/PRR recognition system in modern agriculture.\r\nWe are focused to study in Peach two well described MAMP\/PRR recognition model systems: flg22\/FLS2 and xyn11\/LeEIX2 recognition system. In the case of Flg22\/FLS2 recognition system a conserved flagellin peptide, named flg22, is recognized by the PRR FLS2, activating oxidative burst, hormone production and transcriptional activation of Pathogen related (PR) genes. In xyn11\/LeEIX2 recognition system a conserved peptide of endoxylanases type 11, named hereinafter xyn11, is recognized by the PRR EIX2, activating oxidative burst, ethylene production, expression of PR proteins and hypersensitive response. These recognition systems are agriculturally important because they can recognize the bacteria Bacillus sp, Pseudomonas sp and Xanthomonas sp and the fungi Trichoderma viridea and Botrytis cinerea. Remarkably, Bacterial Canker caused by Pseudomonas syringae is a current problem for Peach crops in Chile, as well, grey mold caused by Botrytis cinerea infection is a common post-harvesting disease for fruits.\r\nPeach immunity is poorly described, however transcriptomic analysis showed more than 20 PRR like proteins induced by Xanthomonas arboricola infection and QTL analysis have identified two RLK genes associated to peach resistance against Monilinia spp, the causal agent of brown rot blossom blight, one of the most economically important peach diseases. However, no functional analyses have described MAMP\/PRR recognition systems in peach to date. We expect to generate novel and valuable information regarding Peach immunity, characterizing peach flg22\/FLS2 and xyn11\/LeEIX2 recognition systems, as well as the defense responses triggered by them and their involvement in resistance to Pseudomonas syringae and Botrytis ciniera. In addition, we will explore whether these recognition systems, particularly xyn11\/LeEIX2 participate in Monilinia spp recognition.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2020 - Noviembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26818\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Dise\u00f1o e implementaci\u00f3n de diagn\u00f3stico de estigma asociado a salud mental en poblaci\u00f3n seleccionada.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26818\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26818\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El estigma asociado a salud mental es uno de los problemas m\u00e1s importantes de la salud mental con perspectiva de salud p\u00fablica hoy, concitando \u0096 en diversos grados de avance - desarrollo acad\u00e9mico, pol\u00edticas\r\np\u00fablicas, acciones locales y participaci\u00f3n de la sociedad civil.\r\nA nivel de pol\u00edticas en salud todav\u00eda hay una importante brecha que completar. En 2010, ya el estigma era parte de los temas definidos en la Estrategia Nacional de Salud, dentro del eje estrat\u00e9gico de \u0093Enfermedades no transmisibles, violencia y discapacidad\u0094, bajo el resultado esperado \u0093Promover la inclusi\u00f3n social de las personas con discapacidad de origen mental\u0094, por ejemplo, se plate\u00f3 el resultado de \u0093Contar con un plan regional para reducir estigma hacia personas con problemas o trastornos mentales\u0094. Si bien esto moviliz\u00f3 algunos desarrollos regionales, esto no alcanz\u00f3 a todo el pa\u00eds. Por esta raz\u00f3n, el Plan Nacional de Salud Mental 2017-2025 volvi\u00f3 a retomar el tema. Esta vez, asign\u00e1ndole mayor prioridad, lo cual queda plasmado en el plan de acci\u00f3n asociado, donde la materia tiene una l\u00ednea espec\u00edfica.\r\nEl objetivo de la l\u00ednea es \u0093reducir el estigma relacionado a problemas de salud mental\u0094 y cuenta entre sus principales iniciativas con:\r\n\u0095 Dise\u00f1ar e implementar un plan para abordar el estigma relacionado con la salud mental\r\n\u0095 Desarrolla un levantamiento sistem\u00e1tico de informaci\u00f3n acerca de buenas pr\u00e1cticas sobre estigma en la salud\r\nmental, en la red de salud, la sociedad civil y el mundo acad\u00e9mico.\r\n\u0095 Realizar un Diagn\u00f3stico de estigma asociado a salud mental en poblaci\u00f3n seleccionada[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> SOCHED 2020-03<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2020 - Diciembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Sociedad Chilena de Endocrinolog\u00eda y Diabetes<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26612\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            COVID-DIAB: CARACTERIZACI\u00d3N GEN\u00c9TICA Y EPIGEN\u00c9TICA DE SUJETOS ADULTOS CON DIAGN\u00d3STICO DE DIABETES DE NUEVA APARICI\u00d3N POSTERIOR A COVID-19\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26612\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26612\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Estudio de casos de Diabetes Mellitus de nueva aparici\u00f3n[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ACTO190001<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2020 - Octubre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26215\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Deep insight in the cherry plant defense responses to bacterial canker disease in a scenario of water restriction\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26215\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26215\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Cumplo un rol de Investigador Asociado.\r\n\r\nWhich are the molecular and physiological mechanisms involved in priming and defense activation in cherry plants upon Pss infection? \r\nAre these mechanisms differentially activated between susceptible and resistance cherry varieties? \r\nDo susceptible and resistance cherry varieties present a differential priming under different PRIs exposure? \r\n\r\nEven more, the increasing of aridity and drought in the North of the country, the advancing desert toward the South and a\r\nreduction in water resources in the central zone of Chile, are expected along the XXI century. In this scenario of climate change, other question arises: Which are the molecular and physiological mechanisms involved in priming and defense activation in cherry plants upon Pss infection combined with water deficit? \r\n\r\nThrough this proposal, we intend to answer to these questions, in order to establish the basis for optimize the control of the bacterial canker in cherry fruit tree, by strategies that provide for the use of resistance inductors.\r\nWe propose two hypotheses: a) Cherry cultivars with differential susceptibility to bacterial canker, caused by Pseudomonas syringae pv. syringae, present genetic differences in the molecular machinery of plant immunity; b) Pseudomonas syringae pv. syringae infection is enhanced by water restriction due to an alteration of the molecular machinery of plant immunity.\r\n\r\nThe aims of this proposal is to obtain a better understanding of the plant-pathogen molecular interactions of sweet cherry bacterial canker in relationship with water deficit, using mainly omics strategies.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ACTO190001<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2020 - Octubre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26387\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Deep insight in the cherry plant defense responses to bacterial canker disease in a scenario of water restriction\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26387\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26387\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Cumplo un rol de Investigador Asociado.\r\n\r\nWhich are the molecular and physiological mechanisms involved in priming and defense activation in cherry plants upon Pss infection? \r\nAre these mechanisms differentially activated between susceptible and resistance cherry varieties? \r\nDo susceptible and resistance cherry varieties present a differential priming under different PRIs exposure? \r\n\r\nEven more, the increasing of aridity and drought in the North of the country, the advancing desert toward the South and a\r\nreduction in water resources in the central zone of Chile, are expected along the XXI century. In this scenario of climate change, other question arises: Which are the molecular and physiological mechanisms involved in priming and defense activation in cherry plants upon Pss infection combined with water deficit? \r\n\r\nThrough this proposal, we intend to answer to these questions, in order to establish the basis for optimize the control of the bacterial canker in cherry fruit tree, by strategies that provide for the use of resistance inductors.\r\nWe propose two hypotheses: a) Cherry cultivars with differential susceptibility to bacterial canker, caused by Pseudomonas syringae pv. syringae, present genetic differences in the molecular machinery of plant immunity; b) Pseudomonas syringae pv. syringae infection is enhanced by water restriction due to an alteration of the molecular machinery of plant immunity.\r\n\r\nThe aims of this proposal is to obtain a better understanding of the plant-pathogen molecular interactions of sweet cherry bacterial canker in relationship with water deficit, using mainly omics strategies.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2020 - Octubre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26449\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Innovative organic amendments obtained by the aerobic composting of pig manures and corn stubbles from local industry, supplied with nanoclays and biochar and the utilization of end-products towards the restoration of metal polluted systems\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26449\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26449\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Soils constitute the largest terrestrial organic carbon (C) pool, which is three times the amount of CO2 currently in the atmosphere and several times the current annual fossil fuel emissions. Thus, increasing net soil C storage can represent a substantial C sink potential with the concomitant effect in the reduction of greenhouse gas (GHG) emissions under climate change scenario. Soils in central areas of Chile showed very low organic C levels as consequence of an intensive activity of different industries such as agriculture and mining. In this sense, the high incorporation of agrochemicals in conventional and intensive agriculture and the inadequate disposal of wastes in mining operations can negatively impact the different natural and agro-ecosystems, with detrimental effects on the soil ranging from erosion, loss of organic matter (OM) and C, and a large accumulation of trace elements, which ultimately results in a significant decrease in the quality of this resource. A significant increase in the accumulation of a wide range of heavy metals in the soil, including copper, lead, cadmium and zinc among others have been widely described and associated to mining and agricultural industries.\r\nOn the other hand, under the context of sustainable agriculture, the use of agricultural wastes and thus the recycling of nutrients through biotechnological strategies is receiving increasing attention. Globally, the annual production of agricultural residues is approximately 3.7 Pg of dry matter. Straw, roots, stems and other tissues of corn, wheat and rice, are the main annual crop residues, which represent approximately 40.6%, 24.2% and 15.7%, respectively, of world production. Moreover, according to the literature, approximately 3.8 billion tons of livestock (pig and cow) and poultry manure is produced annually. For the sustainable management of these residues, aerobic composting has served as technological approach to transform this organic material into soil amendments used to increase C stock and improve different physical, chemical and biological properties of soil. However, some type of composts is degraded relatively fast under field conditions producing important nutrient losses and GHG emissions among others.\r\nThe utilization of clay minerals and recalcitrant C sources as pyrogenic C (biochar) produced by pyrolysis, have gained increasing interest as additives of composting operations, due to their influence in the reduction of GHG emissions and their effectivity in the stabilization of C both in compost and soils, leading to a cleaner compost production (reduced in emissions and leaching) and potentially C sequestrant amendments. In our previous research we reported an increase in the stabilization of C during the composting of beef manure and wheat straw mixtures and the potential sequestration of C once end-products were applied to grassland soil by the effect of halloysite (nanoclay) and oat-based biochar applied as additives. Therefore, and taking into account the positive effect related to the utilization of these additives in the composting mixture, to know how the composting process of pig manure-slurry (which is highly in heavy metal contents and GHG and odors emissions) and corn stubble can be affected by the utilization of these additives (e.g., biochar and halloysite nanoclay) in the stability of the final product has not been studied yet and result as an interesting topic of research. Moreover, the influence of additives in GHG emissions, odors, C stabilization, metal availability and the main physico chemical and biological properties during the process of composting of these organic material mixtures is also not known. Furthermore, to understand how the incorporation of this additives can also contribute in the accumulation of C and potential C sequestration once end-products are applied to metal polluted soils, and how the produced amendments affects the metal availability in soil also needs to be elucidate. Hence, this proposal suggests as main objectives 1.- To study the influence of oat based-biochar and halloysite nanoclay as additives in the composting of pig manure-slurry\/corn stubble and\r\n2.- To evaluate the effects of the end-products from composting process in the restoration of metal polluted soils from mining and agricultural industries. In a first stage, a composting study using agricultural waste co-composted with biochar and nanoclays will be conducted wherein C stabilization and gas emissions will be analyzed. Then, in order to determine the decomposition and the environmental impacts of compost in soils such as nutrient leaching and gas emissions, the produced compost will be mixed with soil and incubated. Finally, with the aim to analyze the impacts of compost in metal availability in heavy metal polluted soil, a mesocosm experiment under greenhouse conditions, and field trials will be conducted. For a better understanding of C stabilization, GHG emission, heavy metal availability and the potential mechanisms associated to the process, analytical techniques such as stable C isotope ratios (&#948;13C), CPMAS13CNMR spectroscopy and ICP-OES spectroscopy will be used in collaboration with the Instituto de Recursos Naturales y Agrobiolog\u00eda de Sevilla, Spain (IRNAS-CSIC) and ICA-CSIC Madrid. It expects that the use of described additives will improve the composting of pig manure-slurry mixture producing amendments able to be efficiently used in the remediation of contaminated soils by increasing the preservation of C and reducing the availability of heavy metals minimizing its environmental impacts and losses[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2020 - Diciembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26540\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Efectos de la cuarentena en el aprendizaje asociativo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26540\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26540\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La cuarentena es una medida de respuesta ante brotes de s\u00edndrome respiratorio agudo grave. Permanecer en cuarentena implica mantenerse en un lugar, a veces aislado de otras personas, con exposici\u00f3n a informaci\u00f3n negativa en los medios y con alta incertidumbre respecto a su duraci\u00f3n. Existen varias consecuencias negativas en la salud mental de las personas producto de las medidas de cuarentena (Brooks y cols., 2020; Iasevoli y cols., 2020). Por ejemplo, la gente que ha pasado por cuarentenas demuestra s\u00edntomas de trastornos de ansiedad y depresi\u00f3n; as\u00ed mismo, algunas condiciones como la duraci\u00f3n de la cuarentena incrementan la prevalencia de s\u00edntomas (Hawryluck y cols., 2004). Adem\u00e1s, las noticias e informaci\u00f3n sobre la cuarentena son un factor de estr\u00e9s que pueden aumentar los niveles de ansiedad de la poblaci\u00f3n (Brooks y cols., 2020). Considerando estos efectos, es relevante examinar si el confinamiento y las noticias de la pandemia afectan la ansiedad y el rendimiento en tareas de aprendizaje.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2020 - Diciembre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26248\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Laboratorio de diagn\u00f3stico Universidad de O\u0092Higgins ETAPA 3\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26248\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26248\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26336\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            On the role of coherent structures on wave turbulence\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26336\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26336\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las ondas y las estructuras coherentes est\u00e1n presentes como entidades individuales en varios contextos f\u00edsicos, astron\u00f3micos y geof\u00edsicos, y particularmente en los fluidos. Las situaciones realistas generalmente involucran a ambos, lo que lleva a procesos de interacci\u00f3n complejos que son dif\u00edciles de separar y desenredar. En esta propuesta nos enfocamos en estudiar experimentalmente c\u00f3mo la presencia de estructuras coherentes, tales como v\u00f3rtices o singularidades, afectan las propiedades de las ondas superficiales en un r\u00e9gimen turbulento. Para ello, construiremos dos montajes experimentales para poder estudiar de forma sistem\u00e1tica las propiedades estad\u00edsticas de las ondas cuando interact\u00faan con las estructuras mencionadas. Ambos sistemas tienen la ventaja de que, ajustando los par\u00e1metros de forzamiento, podemos controlar la aparici\u00f3n e intensidad de las estructuras. Por lo tanto, un estudio sistem\u00e1tico de su influencia en turbulencia de ondas (WT) es sencillo.\r\nLa naturaleza intermitente del campo de ondas, as\u00ed como los mecanismos detr\u00e1s de la ruptura del espectro de WT en presencia de estas estructuras son algunas de las preguntas que pretendemos responder. Para abordar estas preguntas, proponemos realizar mediciones espaciotemporales, como la fotograf\u00eda de luz difusa (DLP) y la velocimetr\u00eda de imagen de part\u00edculas (PIV). Los resultados que surjan de esta investigaci\u00f3n podr\u00edan ser de gran importancia para una teor\u00eda que, si bien es v\u00e1lida en muchos sistemas, a\u00fan est\u00e1 incompleta. Las aplicaciones de los resultados a otros sistemas, como los flujos geof\u00edsicos, tambi\u00e9n podr\u00edan ser posibles y bastante relevantes para una amplia comunidad.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2020 - Noviembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26400\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Chronic exposition to anticholinesterase pesticides\u0092 effects on Hidden Hearing Loss and auditory processing development\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26400\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26400\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto tiene como objetivo investigar y esclarecer un mecanismo relacionado con la p\u00e9rdida auditiva\r\nvinculada a la exposici\u00f3n a pesticidas. Nos centramos en comprender los efectos cr\u00f3nicos, no agudos, de la\r\nexposici\u00f3n a pesticidas, particularmente en habitantes de zonas rurales cercanas a campos de cultivo. As\u00ed,\r\nnuestro grupo de estudio estuvo constituido por j\u00f3venes residentes o trabajadores de \u00e1reas lim\u00edtrofes a\r\ncampos de cultivo, donde investigamos la posible asociaci\u00f3n entre la disfunci\u00f3n colin\u00e9rgica del sistema\r\nauditivo eferente, inducida por pesticidas anticolinester\u00e1sicos, y su relaci\u00f3n con la p\u00e9rdida auditiva y trastornos\r\nen el procesamiento central.\r\nNuestra hip\u00f3tesis condujo a la creaci\u00f3n de un modelo experimental que sugiere que la exposici\u00f3n a pesticidas\r\norganofosforados est\u00e1 relacionada con el desarrollo temprano de una p\u00e9rdida auditiva oculta mediada por la\r\ndisfunci\u00f3n del sistema eferente auditivo, el cual est\u00e1 estrechamente asociado con sinapsis colin\u00e9rgicas.\r\nNuestros resultados revelaron que la exposici\u00f3n a pesticidas en j\u00f3venes gener\u00f3 problemas relacionados con\r\nla percepci\u00f3n de tonos de alta frecuencia en los registros audiom\u00e9tricos, una disminuci\u00f3n en la amplitud\r\nasociada a la conducci\u00f3n del nervio auditivo y una reducci\u00f3n en la fuerza del reflejo eferente auditivo. Sin\r\nembargo, no se observaron efectos en la percepci\u00f3n auditiva en los voluntarios j\u00f3venes expuestos a\r\npesticidas.\r\nAdicionalmente, este estudio busc\u00f3 establecer una conexi\u00f3n entre los cambios observados en humanos y los\r\nefectos en animales de experimentaci\u00f3n. Para abordar ello, realizamos estudios en ratones, asign\u00e1ndolos a\r\nuno de cuatro grupos experimentales: dos grupos de ratones Wild Type (WT) y dos grupos de ratones\r\ngen\u00e9ticamente modificados (KO) para silenciar funcionalmente el receptor &#945;9\/&#945;10 en la sinapsis olivococlear\r\nmedial. Esta sinapsis, de naturaleza colin\u00e9rgica, es crucial en el eferente auditivo y se comunica directamente\r\ncon las c\u00e9lulas ciliadas externas.\r\nEstos ratones fueron separados seg\u00fan su genotipo y expuestos a Clorpirifos (0,5mg\/kg) mediante inyecciones\r\nintraperitoneales durante 10 d\u00edas, o recibieron solo el veh\u00edculo (aceite de ma\u00edz). Los estudios en animales\r\nrevelaron un aumento significativo en los umbrales auditivos a las 48 horas, aunque este efecto no persisti\u00f3 a\r\nla cuarta semana post-exposici\u00f3n, tanto en ratones WT como KO. Actualmente, estamos analizando\r\nmicrofotograf\u00edas electr\u00f3nicas para establecer un mecanismo asociado a la p\u00e9rdida de sensibilidad y\r\npercepci\u00f3n auditiva inducida por la exposici\u00f3n a organofosforados. Este an\u00e1lisis est\u00e1 pendiente para su\r\npublicaci\u00f3n.\r\nNuestro estudio permiti\u00f3 describir detalladamente el efecto de la exposici\u00f3n a pesticidas en individuos que\r\nresiden cerca de \u00e1reas de cultivo, mostrando un impacto en la sensibilidad y percepci\u00f3n auditiva. Este efecto\r\npodr\u00eda estar asociado, en parte, a la disfunci\u00f3n colin\u00e9rgica inducida por ciertos pesticidas, especialmente los\r\norganofosforados. Este estudio ha sido crucial para formar grupos de trabajo que investiguen el impacto del\r\nuso de pesticidas en la regi\u00f3n, particularmente en la regi\u00f3n de O\u0092Higgins, donde la actividad predominante es\r\nla agricultura y la mayor parte del empleo se concentra en este sector. Sin embargo, todav\u00eda estamos\r\npendientes de llegar a comunidades m\u00e1s distantes, para llevar a cabo un trabajo de divulgaci\u00f3n cient\u00edfica m\u00e1s\r\namplio y tener un mayor impacto en la sociedad.\r\nDesde una perspectiva cient\u00edfica, nuestro estudio es pionero al intentar establecer un mecanismo que vincule\r\nla p\u00e9rdida auditiva con la exposici\u00f3n a pesticidas. Es el primer estudio en describir en detalle los efectos de\r\nestos qu\u00edmicos en j\u00f3venes expuestos cr\u00f3nicamente, y el primero en explorar el impacto de la exposici\u00f3n a\r\npesticidas en el sistema auditivo a trav\u00e9s de un modelo animal.\r\nEn resumen, este estudio sentar\u00e1 las bases para investigaciones m\u00e1s exhaustivas sobre el fuerte impacto de\r\nla exposici\u00f3n a pesticidas en la audici\u00f3n humana, un \u00e1rea a\u00fan poco explorada. Adem\u00e1s, proporcionar\u00e1\r\nevidencia para comprender, desde una perspectiva de las ciencias b\u00e1sicas, los efectos de las sustancias\r\nanticolinester\u00e1sicas en el funcionamiento de la sinapsis olivococlear medial.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> Proyecto de investigaci\u00f3n SOCHED No 2020-08<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2020 - Mayo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Sociedad Chilena de Endocrinolog\u00eda y Diabetes<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26419\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Efecto del aceite de quinoa (Chenopodium quinoa) en la activaci\u00f3n de NF-&#954;B y Nrf2 y en los niveles de TNF-&#945; y HO-1 inducidos por lipopolisac\u00e1rido en hepatocitos humanos HepG2\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26419\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26419\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]T\u00edtulo: \"Efecto del aceite de quinoa (Chenopodium quinoa) en la activaci\u00f3n de NF-&#954;B y Nrf2 y en los niveles de TNF-&#945; y HO-1 inducidos por lipopolisac\u00e1rido en hepatocitos humanos HepG2\".[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2020 - Octubre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26497\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Evaluaci\u00f3n del Impacto de la Pandemia por COVID &#8211; 19 en las PyMEs colaboradores con los Centros de Desarrollo de Negocios en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26497\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26497\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La actual pandemia ha provocado efectos econ\u00f3micos que deterioran la calidad de vida de millones de ciudadanos(as). Estos efectos han sido particularmente pronunciados en hogares que subsisten gracias a la actividad de las empresas de menor tama\u00f1o. En Am\u00e9rica Latina y el Caribe, el 57% de los hogares con peque\u00f1as empresas han tenido que cerrar sus negocios, generando un alza importante en el desempleo (Bottan, Hoffmann y Vera-Cossio, 2020).\r\n\r\nNos hemos asociado con SERCOTEC para comprender mejor c\u00f3mo la pandemia est\u00e1 afectando el desempe\u00f1o de las empresas en Chile. El objetivo es medir los efectos de la pandemia en las ventas, empleo, ahorro, endeudamiento y subsistencia de las empresas de menor tama\u00f1o; as\u00ed como tambi\u00e9n examinar los mecanismos a trav\u00e9s de los que\r\ndichas empresas se han visto afectadas. Adem\u00e1s, el estudio busca explorar el rol de los Centros de Desarrollo de Negocios (CDNs) mitigando el impacto de la pandemia y c\u00f3mo \u00e9sta ha exacerbado los efectos negativos de la crisis social.\r\nPara ello, el estudio propone dos encuestas por Internet a los clientes de los CDNs en Chile. Los resultados del\r\nestudio buscan ser un insumo crucial en el dise\u00f1o de las pol\u00edticas p\u00fablicas y programas para la reactivaci\u00f3n inclusiva de la econom\u00eda de Chile[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11200561<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2020 - Octubre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26541\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Value-driven attentional capture: an exploration of its boundaries and effects on behavior\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26541\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26541\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Attention is a cognitive process which allows the allocation of cognitive resources to different aspects of the sensory input received by the organism. Of particular interest has been the relation between attention and learning. More specifically, it is commonly assumed, as shown by the evidence, that attention is sensitive to the informational value of the events, that is, the information that some events provide regarding other more relevant stimuli. Several learning theories have proposed specific mechanisms to account for this relation between learning and attention. The Mackintosh model, for instance suggested that the organism provides attention to the events about which it is supposed to learn, when said events are predictive of subsequent, more relevant outcomes. Attention also in turn affects the ability of subjects to learn about specific events that they have already experienced, as shown by the \u0093learned predictiveness\u0094 effect. The results typically show that new associations are learned faster by the participants when they include predictive cues compared to non-predictive or neutral events.\r\nA recent research line has shown that the informational value is not the only factor affecting the interaction between attention and learning, but that the motivational value of the stimuli also modulates it. A growing corpus of evidence on the so-called \u0093reward learning\u0094 or \u0093learned value\u0094 has evidenced that attention can be captured by stimuli associated with reward, even when the resulting learning is irrelevant or even counterproductive to the cognitive task. The evidence for this effect comes mainly from tasks involving monetary reward, in which a specific stimulus (e.g., a red triangle) must be located on a screen by the participants among a set of distractors. Success in locating the target stimulus across trials includes a small monetary reward. The evidence has shown that such a task results in faster learning for the target stimuli, indicating higher attention to the target cue; it also results in disruption of alternative tasks when the target stimulus is presented. Value-driven attentional capture also occurs with stimuli of different value, such as aversive cues instead of rewarding ones, showing that the effect appears to be one of general motivational value instead of one based solely on reward.\r\nThe present project has three aims. The first one is to investigate whether there is any symmetry in the associative mechanisms behind value-driven attentional capture and other learning processes; the second is to examine perceptual conditions and behavioral manipulations that may affect attentional capture. The third objective is to examine the effects of value-modulated attentional capture on behavioral tasks designed to assess the relation between attention and goal-directed behavior. The first objective has been examined to some extent: some factors such as size of reward, and valence of the outcome have been tested, but several questions remain to be examined, such as the manner in which the motivational and informational value of the outcome interact, as well as the effect of extinction or outcome devaluation. Research line 1 will explore whether there are analogues to the \u0093predictiveness\u0094 effects in value-driven attentional capture; research line 2 will examine whether attentional capture is sensitive to interference treatments such as extinction, counter-conditioning and context change; finally, research line will explore the possibility of operant behavior being affected by value-modulated attentional capture.\r\nThe present project will implement on a computer a behavioral task similar to the one described above. Participants will have to visually locate a target stimulus between several distractors, and will be rewarded after successful attempts. The validity of the task will be further included by assessing its effects in both appetitive and aversive learning. The effect of attentional capture on operant behavior will be assessed by asking the participants to perform a reward-seeking task in presence of distractors of different valence. The amount of reward received, latency of responding in front of both target and distractor stimuli, and also ocular movements will be registered as measures of learning and attention, respectively.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2020 - Octubre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26546\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            1120041: Pragmatic awareness and immigrant communities\u0092 acquisition of a third language (L3): A study on EFL classroom teaching practices and pragmatic awareness of Haitian primary school children in Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26546\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26546\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetivo principal del proyecto consiste en explorar c\u00f3mo ni\u00f1os y ni\u00f1as haitianas que viven en Chile aprenden y desarrollan la habilidad pragm\u00e1tica en ingl\u00e9s como una tercera lengua (L3) en contextos de ense\u00f1anza del ingl\u00e9s como lengua extranjera (L2) en contextos educativos formales y multiculturales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> Proyecto de investigaci\u00f3n SOCHED No 2020-08<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2020 - Mayo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Sociedad Chilena de Endocrinolog\u00eda y Diabetes<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26554\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Efecto del aceite de quinoa (Chenopodium quinoa) en la activaci\u00f3n de NF-&#954;B y Nrf2 y en los niveles de TNF-&#945; y HO-1 inducidos por lipopolisac\u00e1rido en hepatocitos humanos HepG2\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26554\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26554\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]T\u00edtulo: \"Efecto del aceite de quinoa (Chenopodium quinoa) en la activaci\u00f3n de NF-&#954;B y Nrf2 y en los niveles de TNF-&#945; y HO-1 inducidos por lipopolisac\u00e1rido en hepatocitos humanos HepG2\".[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11201259<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2020 - Octubre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26562\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Qualitative Properties of Weighted and Anisotropic Variational Problems\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26562\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26562\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En los campos de investigaci\u00f3n de An\u00e1lisis, Ecuaciones en Derivadas Parciales y Geometr\u00eda, as\u00ed como en otras \u00e1reas como la F\u00edsica Experimental, F\u00edsica Te\u00f3rica y Ciencias de los Materiales, un gran foco de atenci\u00f3n se pone en explorar las cuestiones de existencia y descripci\u00f3n cualitativa de puntos cr\u00edticos a problemas variacionales, los cuales dependen de par\u00e1metros que surgen naturalmente en el modelamiento de fen\u00f3menos en los campos antes mencionados. Igualmente importante es el entendimiento de las propiedades de rigidez de estos modelos, a saber, decidir si la existencia y propiedades cualitativas de tales puntos cr\u00edticos se mantienen, o cambian abruptamente, cuando los valores de los par\u00e1metros var\u00edan. \r\n\r\nEn las \u00faltimas d\u00e9cadas, se ha logrado un gran progreso en estas direcciones - desde el punto de vista del an\u00e1lisis matem\u00e1tico - en dos clases de problemas variacionales que comparten ``caracter\u00edsticas de isotrop\u00eda sin pesos\": los funcionales son constru\u00eddos de manera que, a grandes rasgos, las funciones\/conjuntos son penalizados independientemente de la posici\u00f3n, y no hay direcciones preferidas o distinguidas. El primer problema corresponde al modelo de gotas l\u00edquidas de Gamow, el cual es un problema isoperim\u00e9trico con un t\u00e9rmino adicional no-local de tipo Riesz, propuesto originalmente para describir la existencia\/no-existencia y caracter\u00edsticas geom\u00e9tricas del n\u00facleo at\u00f3mico, en f\u00edsica nuclear, dependiendo de un par\u00e1metro de masa. El segundo, es sobre el estudio de existencia y propiedades cualitativas de v\u00f3rtices para la energ\u00eda de Ginzburg-Landau (GLE), usada para describir defectos en superflu\u00eddos y f\u00edsica de materia condensada. En los a\u00f1os recientes, los investigadores se han dedicado a proponer y explorar variantes del modelo variacional antes descrito, donde el funcional de energ\u00eda asociado adquiere pesos o anisotrop\u00edas, en un intento por capturar fen\u00f3menos m\u00e1s finos y delicados encontrados en experimentos, as\u00ed como para extender la teor\u00eda matem\u00e1tica a contextos m\u00e1s generales.\r\n\r\nLos objetivos principales del proyecto son el estudio de existencia, y propiedades cualitativas as\u00ed como de rigidez para: (1) versiones con pesos del modelo de gotas l\u00edquidas, donde un funcional de per\u00edmetro reemplaza al per\u00edmetro usual en el sentido de De Giorgi, y (2) una version anisotr\u00f3pica de la energ\u00eda de Ginzburg-Landau derivada del modelamiento de defectos umbilicales en un l\u00edmite 3D a 2D de cristales l\u00edquidos nem\u00e1ticos, en un r\u00e9gimen f\u00edsico que favorece el comportamiento anisotr\u00f3pico.\r\n\r\nConcretamente, la primera parte del proyecto buscar establecer existencia, acotamiento y regularidad optimal para conjuntos que minimizan el funcional isoperim\u00e9trico con pesos m\u00e1s un potencial no-local, para una clase de pesos continuos que se asumen degenerados (valen cero en una cantidad finita de puntos) y coercivos en infinito. Adem\u00e1s, esperamos probar una propiedad de rigidez en cuanto a la forma del minimizantes (unicidad): debe ser una bola, para un rango adecuado del par\u00e1metro de masa. Adicionalmente, planeamos argumentar rigurosamente el fen\u00f3meno de fragmentaci\u00f3n infinita, cuando los valores del par\u00e1metro de masa tienden a cero. Esto requiere del entendimiento y  adaptaci\u00f3n de multiples heramientas profundas y sofisticadas en la teor\u00eda de medida geom\u00e9trica y el c\u00e1lculo de variaciones, que incluye: una versi\u00f3n geom\u00e9trica del principio de concentraci\u00f3n compacidad de Frank y Lieb; la teor\u00eda de regularidad est\u00e1ndar para conjuntos quasi-minimizantes en el contexto sin pesos, as\u00ed como la adaptaci\u00f3n de resultados de regularidad muy recientes de Pratelli y Saracco para conjuntos isoperim\u00e9tricos con pesos (sin t\u00e9rmino no-local); la celebrada desigualdad isoperim\u00e9trica cuantitativa ajustada de Fusco, Maggi and Pratelli y la estrategia de Acerbi, Fusco and Morini para mostrar rigidez de minimizadores (en el marco isotr\u00f3pico), entre otros. A este respecto, resaltamos un resultado reciente obtenido por el Investigador Principal sobre la existencia y regularidad de funciones con menor gradiente con pesos, un problema que est\u00e1 muy relacionado con el problema isoperim\u00e9trico con pesos.\r\n\r\nConcerniendo la segunda parte del proyecto, nuestro punto de partida es el trabajo de Clerc-D\u00e1vila-Vidal Henr\u00edquez-Kowalczyk quienes derivaron una version anistr\u00f3pica de la energ\u00eda GLE y estudiaron como la anisotrop\u00eda quiebra algunas invarianzas de la asociada ecuaci\u00f3n de GL. Las soluciones tipo-v\u00f3rtice ahora consisten de un conjunto discreto (restricci\u00f3n en la fase), y para cada una ellos argumentan heur\u00edsticamente su estabilidad\/inestabilidad, como una funci\u00f3n del par\u00e1metro de anisotrop\u00eda. El objectivo principal de este parte del proyecto es analizar rigurosamente la propiedades de estabilidad\/inestabilidad lineal de soluciones tipo-v\u00f3rtice sim\u00e9tricas (defectos puntuales) para la GLE anisotr\u00f3pica, dependiendo del tama\u00f1o del n\u00facleo de la soluci\u00f3n. Para lograr estas metas se propone adaptar herramientas clave en el an\u00e1lisis de estabilidad de la energ\u00eda, tales como \"Fourier-splitting\" y ortogonalidad de formas cuadr\u00e1ticas, de Mironescu; y el approach de del Pino-Felmer-Kowalczyk basado en decomposiciones tipo-Hardy, usado para argumentar la no-degeneracia de la forma cuadr\u00e1tica asociado al v\u00f3rtice de grado-uno de GL; entre otros. Al IP le gustar\u00eda extender el an\u00e1lisis de estabilidad para soluciones de tipo-v\u00f3rtice para la GLE anisotr\u00f3pica que no son sim\u00e9tricas (v\u00f3rtices con  ``carga topol\u00f3gica\" negativa). Este es un problema mucho m\u00e1s desafiante, ya que la representaci\u00f3n polar de la soluci\u00f3n no se desacopla en una parte radial y otra angular, de manera uni-dimensional. Finalmente, otro resultado de inter\u00e9s independente consiste en establecer existencia de soluciones tipo-v\u00f3rtice generales para la GLE anisotr\u00f3pica sin restricci\u00f3n en la fase; esto causa que el perfil radial sea a valores complejos, una caracter\u00edstica fundamentalmente distinta comparada con aquella del caso isotr\u00f3pico. \r\n\r\nEn resumen, este proyecto buscar dar una contribuci\u00f3n sustancial a la teor\u00eda de problemas variacionales geom\u00e9tricos con pesos y a la teor\u00eda de estabilidad de soluciones tipo-v\u00f3rtice para versiones anisotr\u00f3picas de energ\u00edas tipo Ginzburg-Landau, las cuales se estan convirtiendo en una foco de investigaci\u00f3n profusa en la comunidad de An\u00e1lisis No-Lineal. El desarrollo de herramientas y la adaptaci\u00f3n de nuevas t\u00e9cnicas del An\u00e1lisis nos permitir\u00e1 obtener un mayor entendimiento sobre los mecanismos que influencian la existencia, propiedades cualitativas y de rigidez, en la presencia de pesos y anisotrop\u00edas para los tipos de problemas variacionales propuestos. Esperamos esto llevar\u00e9 a nuevas direcciones de investigaci\u00f3n en problemas relacionados dentro del C\u00e1lculo de Variaciones, Teor\u00eda de Medida Geom\u00e9trica, y Ecuaciones en Derivadas Parciales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11201337<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26613\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Consequences of androgen excess on folate metabolism and epigenetic effects on metabolic phenotype in Chilean women with polycystic ovary syndrome (PCOS).\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26613\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26613\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Polycystic ovary syndrome (PCOS) is a prevalent and multifactorial endocrine disorder in women, which is\r\ncharacterized by reproductive and metabolic alterations that include hyperandrogenism, polycystic ovarian \r\nmorphology, anovulation, insulin resistance, dyslipidemia and obesity with a high risk to develop type 2 \r\ndiabetes and cardiovascular disease. However, the mechanisms that contribute to the development \r\nof metabolic abnormalities are not completely understood. Currently, DNA methylation, an epigenetic \r\nmechanism that regulates gene expression, has been proposed as an attractive possibility that might explain \r\nthe heterogeneity of the syndrome linking the effect of environmental factors on susceptible genes to the \r\npresence of metabolic features. Data from women with PCOS and animal models of hyperandrogenism have \r\nfound differential methylation patterns in several gene promoters related to glucose and lipid metabolism \r\nleading to a dysregulation of the expression of these genes and metabolic disorders. On the other hand, \r\nseveral environmental factors that may contribute with the establishment of these epigenetic modifications \r\nin women with PCOS remain unidentified. In this regard, it is widely accepted that different foods and \r\nnutrients have an impact on the regulation of epigenetic mechanisms, among them it has been \r\nproposed that elevated folic acid (FA) levels could induce an hypermethylation of the DNA which\r\ncould reduce the expression of important regulatory genes including those asociated with \r\nmetabolic function. Interestingly, women with PCOS show changes in folate and homocysteine levels \r\nsuggesting an altered folate metabolism, which could be associated to changes in the methylation patterns \r\nof metabolic genes. In the present research project, we propose that androgen excess disrupts the \r\nfolate cycle leading to folate excess in women with PCOS compared to control women. This \r\nalteration leads to hypermethylation of candidate genes involved in glucose and lipid metabolism \r\n(PPARG, FOXO1, GPAM and APOA2) which may impact the metabolic phenotype of women with \r\nPCOS. To test this hypothesis, 37 women with PCOS and 37 control women will be recruited to assess the \r\neffect of androgen excess in women with PCOS on folate metabolism circulating biomarkers such as folates, \r\nvit B12 and homocysteine (Hcy) (Specific aim 1). These results will be categorized according to quartiles of \r\nfolate consumption according to the dietary pattern, using a validated food frequency questionnaire, and \r\nassociated with circulating androgen levels. In addition, to evaluate whether androgen excess induces \r\nchanges in folate cycle enzymes, gene expression analyses will be performed in peripheral blood mononuclear \r\ncells (PBMC) (Specific aim 2). To establish the causality of our hypothesis, we will evaluate the effect of \r\nandrogen excess on the folate cycle using a cellular model. For this, gene and protein expression of the \r\nenzymes involved on the folate cycle (MAT, SAHH, MS, MTHFR, FOL1R y AHCY) will be analyzed in an \r\nhepatocyte cell line stimulated with testosterone (Specific aim 3). To check the specificity of androgen action\r\nwe will use androgen blockers and aromatase inhibitors. Finally, to determine the effect on genes associated \r\nto glucose and lipid metabolism, DNA methylation in promoter regions and gene expression of candidate \r\ngenes associated to glucose and lipid metabolism (PPARG, FOXO1, GPAM and APOA2) will be analyzed \r\n(Specific aim 4). We expect to find an increase in folate and homocysteine levels, and decreased levels of \r\nvitamin B12 in women with PCOS, asociated with a decreased expression of folate metabolism enzymes. On \r\nthe other hand, in the in vitro model, we expect high levels of folic acid and a decrease in the expression of \r\ngenes involved in folate metabolism in hepatocytes stimulated with androgens. This dysregulation in folate \r\nmetabolism induced by androgen excess may result in hypermethylation of genes involved in lipid and \r\nglucose metabolism such as PPARG, FOXO1, GPAM and APOA2, leading to a lower gene expression which may impact the metabolic parameters of PCOS women. The results obtained from this proposal will help to identify new mechanisms involved in the pathophysiology of metabolic alterations in PCOS leading to the development of more effective strategies of prevention and therapy[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11201028<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2020 - Noviembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26823\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Socio-labor inclusion and stigma among young adults with autism spectrum disorders\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26823\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26823\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The current study will quantify the level of employment in young adults with ASD and identify barriers to and facilitators of their labor inclusion. In addition, this study will determine if the level of stigma is associated with employment rates in young adults with ASD. The overarching goal is to contribute to improve the quality of life in adults with ASD in Chile by informing the development of public policies and interventions to increase the employment rate in this vulnerable population.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ANID\/FONDECYT\/11200916<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2020 - Octubre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27119\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27119\" aria-expanded=\"false\" aria-controls=\"collapse-27119\">\n                                            Geograf\u00eda pol\u00edtica insular: el rol de la insularidad en la gobernanza de Guaitecas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27119\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27119\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Antecedentes\r\nLa insularidad es el resultado de una relaci\u00f3n entre habitantes isle\u00f1os y poderes continentales que est\u00e1 marcada tanto por la geograf\u00eda como por la historia. Por un lado, los l\u00edmites impuestos por el mar como barrera natural dan paso a una identificaci\u00f3n territorial que permite a sus habitantes definir su lugar en el mundo desde su posici\u00f3n geogr\u00e1fica, adem\u00e1s de identificar en otros isle\u00f1os sus pares pues, por otro lado, las islas tienen una trayectoria marcada por la frustraci\u00f3n y el resentimiento hacia los centros de poder, usualmente estatales. Por ello, para estudiarlas es necesario abordar su historia pol\u00edtica, el modo en que participan de din\u00e1micas sociales y productivas y los hitos o eventos que han marcado la percepci\u00f3n de sus habitantes como parte de una comunidad isle\u00f1a.\r\n\r\nComo territorios de peque\u00f1o tama\u00f1o, son vulnerables a presiones que tienen fuerzas dif\u00edciles de contener. Pero en las islas es com\u00fan la adaptaci\u00f3n a nuevos escenarios, y han generado pr\u00e1cticas sociales que les permiten cierto control de la intensidad de estas fuerzas en tanto generan un posicionamiento pol\u00edtico que manifiesta contenidos complejos, dif\u00edciles de reducir a una sola dimensi\u00f3n y que en muchos casos llevan a negociar de un modo que no ocurre en otro tipo de territorios, por aislados que sean. Pero estas fuerzas tambi\u00e9n pueden aplastar todo lo que es espec\u00edfico de las islas, perdi\u00e9ndose en ello la oportunidad de aprovechar el conocimiento y las capacidades de deliberaci\u00f3n en ellas.\r\n\r\nProblema de investigaci\u00f3n\r\nEl problema de investigaci\u00f3n se focaliza en los procesos de posicionamiento pol\u00edtico con especificidad territorial en zonas insulares. En ellos la insularidad importa factores complejos y diversos que se presentan de manera simult\u00e1nea, con efectos sobre las pr\u00e1cticas pol\u00edticas y sociales. No son directamente accesibles para quienes no habitan una isla, por lo que sus formas y contenidos suelen quedar al margen de fuerzas externas, sea por el peque\u00f1o tama\u00f1o de su territorio o porque su capacidad electoral no logra trascender los t\u00e9rminos de la democracia representativa.\r\n\r\nEl objetivo general es comprender el rol de la insularidad en la definici\u00f3n de posiciones pol\u00edticas desde la comuna de Guaitecas, en la regi\u00f3n de Ays\u00e9n. Los objetivos espec\u00edficos son: a) caracterizar los factores que inciden en la toma de posiciones pol\u00edticas en Guaitecas; b) identificar las posiciones pol\u00edticas insulares de Guaitecas desde 1990; c) establecer el modo en que estas posiciones pol\u00edticas insulares son generadas y legitimadas a nivel local; y d) distinguir los cambios en las pol\u00edticas insulares al ser escaladas a los niveles regional y nacional.\r\n\r\nMetodologia\r\nEl caso de estudio de Guaitecas, una comuna-archipi\u00e9lago con 1.843 habitantes, de pasado maderero y presente pesquero y acu\u00edcola, se justifica en que est\u00e1 justo en medio de procesos transformadores de dos fuerzas: la salmonicultura, que en su proceso de expansi\u00f3n desde la regi\u00f3n de Los Lagos hacia el sur tiene en este archipi\u00e9lago un punto nodal para la prestaci\u00f3n de servicios, y la pesca, que tensiona las relaciones entre pescadores artesanales debido a la divisi\u00f3n de las aguas en la asignaci\u00f3n de cuotas de extracci\u00f3n. El sector privado y las agencias estatales lideran dichos procesos en sus propios t\u00e9rminos, mientras que la deliberaci\u00f3n local y el modo en que se articula las posiciones insulares parecen no trascender m\u00e1s all\u00e1 de los l\u00edmites de la comuna.\r\n\r\nLa investigaci\u00f3n emplea m\u00e9todos de investigaci\u00f3n cualitativos. La revisi\u00f3n bibliogr\u00e1fica es el punto de partida para establecer categor\u00edas anal\u00edticas preliminares, mediante an\u00e1lisis tem\u00e1tico, y para orientar el muestreo te\u00f3rico. La entrevista semiestructurada permite acceder a discursos que releven la historicidad y el modo en que se produce el posicionamiento pol\u00edtico en Guaitecas. A trav\u00e9s de la observaci\u00f3n participante se accede a las instancias de deliberaci\u00f3n, permitiendo contrastar y reconocer lo espec\u00edfico del archipi\u00e9lago en su toma de posiciones pol\u00edticas.\r\n\r\nResultados\r\nSe releva el rol de la insularidad en la pol\u00edtica local, a fin de determinar la incidencia de la insularidad en la participaci\u00f3n en el debate p\u00fablico. Tambi\u00e9n se apunta a fortalecer una l\u00ednea de trabajo colaborativa, donde la producci\u00f3n de resultados est\u00e9 continuamente bajo escrutinio de los informantes y de la comunidad bajo estudio. Adem\u00e1s, se documentan las transformaciones de Guaitecas, dadas las tendencias transformadoras que experimenta.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26090\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Nodo de Ciencia Abierta: Co-creaci\u00f3n de un modelo de Ciencia abierta para fortalecer el desarrollo de la ciencia y tecnolog\u00eda en la Macrozona Centro Sur de Chile en concordancia con su territorio y sociedad\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26090\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26090\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto busca conectar al ecosistema de la ciencia y tecnolog\u00eda con las fortalezas y necesidades de la sociedad enmarcado en el territorio de la Macrozona Centro Sur, que abarca las regiones del Libertador Bernando O\u0092Higgins, del Maule, de \u00d1uble y del BioB\u00edo. Se han analizado siete dimensiones relevantes para el desarrollo de la Ciencia como son la infraestructura, el equipamiento disponible, el capital humano, la investigaci\u00f3n, la innovaci\u00f3n y emprendimiento, los laboratorios naturales y el sector productivo. Desde este an\u00e1lisis han emergido las \u00e1reas OECD de la Agricultura, la Ingenier\u00eda, la Educaci\u00f3n y la Salud con potenciales de crecimiento y mayor impacto en sus habitantes.\r\n\r\nLos objetivos espec\u00edficos son: 1) Implementar un modelo de gobernanza de acuerdo a los desaf\u00edos y oportunidades identificadas y que permita mejorar la competitividad de Universidades, Centros de Investigaci\u00f3n, y otras organizaciones representativas del \u00e1mbito p\u00fablico y privado; 2) Fortalecer competencias en innovaci\u00f3n abierta, complejidad de innovaci\u00f3n y ciencia abierta en el ecosistema de ciencia y tecnolog\u00eda, para analizar desaf\u00edos y oportunidades de la macrozona en un lenguaje com\u00fan; 3) Implementar m\u00e9todos y mejores pr\u00e1cticas de Ciencia abierta para su aplicaci\u00f3n en el ecosistema de ciencia y tecnolog\u00eda de la macrozona en el desarrollo de hip\u00f3tesis robustas y conectados con sus capacidades y ventajas territoriales.\r\n\r\nPara realizar esta tarea se crear\u00e1 un comit\u00e9 de coordinaci\u00f3n de la macrozona con la participaci\u00f3n de la SEREMI de CTCI que convocar\u00e1 a acad\u00e9micos de disciplinas m\u00faltiples en concordancia con mesas tem\u00e1ticas transversales y espec\u00edficas, en conjunto con el sector p\u00fablico y privado, grupo que denominaremos el ecosistema de ciencia y tecnolog\u00eda bajo el paradigma de ciencia abierta (eCTCI-CA), para co-crear un modelo de Ciencia abierta aplicado a la discusi\u00f3n de iniciativas las tem\u00e1ticas espec\u00edficas propuestas: 1) Creaci\u00f3n de modelos asociativos para el capital creativo, 2) Estructuras de convergencias de servicios territoriales, 3) Incorporaci\u00f3n de nuevos modelos educativos, 4) Implementaci\u00f3n de datos abiertos para el desarrollo de hip\u00f3tesis, 5) Desarrollo de agricultura de nueva generaci\u00f3n, 6) Inclusi\u00f3n de ruralidad sustentable, 7) Adaptaci\u00f3n al cambio clim\u00e1tico, 8) Desarrollo de Bioeconom\u00eda sostenible, 9) Implementado manufactura avanzada y nanomateriales, 9) Prevenci\u00f3n y resiliencia del desastre, 10) Conectando investigaci\u00f3n b\u00e1sica con la cl\u00ednica aplicada a la salud p\u00fablica.\r\n\r\nDurante la ejecuci\u00f3n del proyecto por 2 a\u00f1os el eCTCI-CA ser\u00e1 guiado en actividades de creaci\u00f3n de confianza y de competencias en el desarrollo de proyectos utilizando metodolog\u00edas de ciencia abierta, innovaci\u00f3n abierta y \u00e1giles. Colaborando en equipos multidisciplinarios con actores claves del sector p\u00fablico y privado para fortalecer la vinculaci\u00f3n de las preguntas de investigaci\u00f3n con el territorio y la sociedad componente.\r\n\r\nEl impacto esperado de este proyecto es fortalecer la vinculaci\u00f3n de las preguntas cient\u00edficas con su territorio y sociedad, generar hip\u00f3tesis y conocimiento desde equipos multidisciplinarios y colaborativos, y de manera rec\u00edproca conectar las pol\u00edticas p\u00fablicas con los requerimientos de eCTCI-CA bajo un paradigma de Ciencia Abierta. Para mantener la sustentabilidad en el tiempo de la iniciativa se propone la creaci\u00f3n de una gobernanza con responsabilidades y liderazgo compartidos entre los asociados al proyecto y la creaci\u00f3n de un modelo de transferencia de conocimiento al sistema p\u00fablico y privado.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26636\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Nodo de Ciencia Abierta: Co-creaci\u00f3n de un modelo de Ciencia abierta para fortalecer el desarrollo de la ciencia y tecnolog\u00eda en la Macrozona Centro Sur de Chile en concordancia con su territorio y sociedad\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26636\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26636\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto busca conectar al ecosistema de la ciencia y tecnolog\u00eda con las fortalezas y necesidades de la sociedad enmarcado en el territorio de la Macrozona Centro Sur, que abarca las regiones del Libertador Bernando O\u0092Higgins, del Maule, de \u00d1uble y del BioB\u00edo. Se han analizado siete dimensiones relevantes para el desarrollo de la Ciencia como son la infraestructura, el equipamiento disponible, el capital humano, la investigaci\u00f3n, la innovaci\u00f3n y emprendimiento, los laboratorios naturales y el sector productivo. Desde este an\u00e1lisis han emergido las \u00e1reas OECD de la Agricultura, la Ingenier\u00eda, la Educaci\u00f3n y la Salud con potenciales de crecimiento y mayor impacto en sus habitantes.\r\n\r\nLos objetivos espec\u00edficos son: 1) Implementar un modelo de gobernanza de acuerdo a los desaf\u00edos y oportunidades identificadas y que permita mejorar la competitividad de Universidades, Centros de Investigaci\u00f3n, y otras organizaciones representativas del \u00e1mbito p\u00fablico y privado; 2) Fortalecer competencias en innovaci\u00f3n abierta, complejidad de innovaci\u00f3n y ciencia abierta en el ecosistema de ciencia y tecnolog\u00eda, para analizar desaf\u00edos y oportunidades de la macrozona en un lenguaje com\u00fan; 3) Implementar m\u00e9todos y mejores pr\u00e1cticas de Ciencia abierta para su aplicaci\u00f3n en el ecosistema de ciencia y tecnolog\u00eda de la macrozona en el desarrollo de hip\u00f3tesis robustas y conectados con sus capacidades y ventajas territoriales.\r\n\r\nPara realizar esta tarea se crear\u00e1 un comit\u00e9 de coordinaci\u00f3n de la macrozona con la participaci\u00f3n de la SEREMI de CTCI que convocar\u00e1 a acad\u00e9micos de disciplinas m\u00faltiples en concordancia con mesas tem\u00e1ticas transversales y espec\u00edficas, en conjunto con el sector p\u00fablico y privado, grupo que denominaremos el ecosistema de ciencia y tecnolog\u00eda bajo el paradigma de ciencia abierta (eCTCI-CA), para co-crear un modelo de Ciencia abierta aplicado a la discusi\u00f3n de iniciativas las tem\u00e1ticas espec\u00edficas propuestas: 1) Creaci\u00f3n de modelos asociativos para el capital creativo, 2) Estructuras de convergencias de servicios territoriales, 3) Incorporaci\u00f3n de nuevos modelos educativos, 4) Implementaci\u00f3n de datos abiertos para el desarrollo de hip\u00f3tesis, 5) Desarrollo de agricultura de nueva generaci\u00f3n, 6) Inclusi\u00f3n de ruralidad sustentable, 7) Adaptaci\u00f3n al cambio clim\u00e1tico, 8) Desarrollo de Bioeconom\u00eda sostenible, 9) Implementado manufactura avanzada y nanomateriales, 9) Prevenci\u00f3n y resiliencia del desastre, 10) Conectando investigaci\u00f3n b\u00e1sica con la cl\u00ednica aplicada a la salud p\u00fablica.\r\n\r\nDurante la ejecuci\u00f3n del proyecto por 2 a\u00f1os el eCTCI-CA ser\u00e1 guiado en actividades de creaci\u00f3n de confianza y de competencias en el desarrollo de proyectos utilizando metodolog\u00edas de ciencia abierta, innovaci\u00f3n abierta y \u00e1giles. Colaborando en equipos multidisciplinarios con actores claves del sector p\u00fablico y privado para fortalecer la vinculaci\u00f3n de las preguntas de investigaci\u00f3n con el territorio y la sociedad componente.\r\n\r\nEl impacto esperado de este proyecto es fortalecer la vinculaci\u00f3n de las preguntas cient\u00edficas con su territorio y sociedad, generar hip\u00f3tesis y conocimiento desde equipos multidisciplinarios y colaborativos, y de manera rec\u00edproca conectar las pol\u00edticas p\u00fablicas con los requerimientos de eCTCI-CA bajo un paradigma de Ciencia Abierta. Para mantener la sustentabilidad en el tiempo de la iniciativa se propone la creaci\u00f3n de una gobernanza con responsabilidades y liderazgo compartidos entre los asociados al proyecto y la creaci\u00f3n de un modelo de transferencia de conocimiento al sistema p\u00fablico y privado.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2020 - Enero 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26709\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Elaboraci\u00f3n de cuaderno de Ingl\u00e9s Escrito II  para el desarrollo de la producci\u00f3n escrita en estudiantes de Pedagog\u00eda en ingl\u00e9s.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26709\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26709\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Durante tres a\u00f1os de experiencia en la ense\u00f1anza de ingl\u00e9s escrito para la carrera Pedagog\u00eda en\r\nIngl\u00e9s para Ense\u00f1anza B\u00e1sica y Media se evidenci\u00f3 que el material de estudio existente, al ser de\r\neditorial extranjera y de uso masivo en la ense\u00f1anza de escritura, no respond\u00eda adecuadamente\r\na las necesidades del contexto de la Universidad de O\u0092Higgins. Por dicha raz\u00f3n, se plante\u00f3 y dise\u00f1\u00f3\r\nel Cuaderno de Ingl\u00e9s Escrito I (Written English I Booklet) el que fue implementado exitosamente\r\ndurante el primer semestre del a\u00f1o acad\u00e9mico 2020 con los estudiantes de esta asignatura. Al\r\nt\u00e9rmino del curso, un n\u00famero importante de estudiantes manifest\u00f3 que notaron un avance\r\nsignificativo en el desarrollo de su habilidad de escritura en ingl\u00e9s, la que fue posible en gran parte\r\npor las tareas de escritura clase a clase planteadas en el Cuaderno. Dado estos resultados, se hace\r\nindispensable la continuidad del Cuaderno para la asignatura de Ingl\u00e9s Escrito II. Este \u00faltimo no\r\ns\u00f3lo continuar\u00e1 siendo aut\u00e9ntico, contextualizado y enfocado en la competencia ling\u00fc\u00edstica, sino\r\nque tambi\u00e9n estar\u00e1 enfocado a la competencia pedag\u00f3gica. Asimismo, dada la contingencia, el\r\ndise\u00f1o contempla la adaptaci\u00f3n de actividades a la modalidad online a trav\u00e9s del Foro de\r\nUcampus, Googledocs, entre otros para as\u00ed mantener su esencia colaborativa.\r\nNuestra propuesta consiste en un ciclo de dise\u00f1o, implementaci\u00f3n y revisi\u00f3n del Cuaderno de\r\nIngl\u00e9s Escrito II. Durante este ciclo, se realizar\u00e1n dos encuestas de opini\u00f3n a los estudiantes de\r\nlas tres secciones de la cohorte 2020, revisiones del cuaderno y reuniones docentes para finalizar\r\ncon un informe de resultados de la implementaci\u00f3n. Como resultados, se espera que los y las\r\nestudiantes consoliden sus aprendizajes para as\u00ed poder comunicarse de manera competente a\r\ntrav\u00e9s de la escritura en ingl\u00e9s. Finalmente, se espera la creaci\u00f3n de un producto digital - el\r\ncuaderno de trabajo para Ingl\u00e9s Escrito II - que contribuir\u00e1 al quehacer docente de los futuros\r\negresados de Pedagog\u00eda en Ingl\u00e9s para Ense\u00f1anza B\u00e1sica y Media, quedando como insumo para\r\nla carrera y la Universidad de O &#769;Higgins.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2020 - Enero 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26710\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Elaboraci\u00f3n de plan piloto de lectura contextualizado para el desarrollo de competencias de comunicaci\u00f3n oral en ingl\u00e9s\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26710\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26710\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El \u00e1mbito de formaci\u00f3n (b) Competencias ling\u00fc\u00edsticas y comunicativas en lengua inglesa, el cual es una caracter\u00edstica de la carrera, tiene por objetivo que los\/as profesores y profesoras de ingl\u00e9s en formaci\u00f3n inicial adquieran y fortalezcan las habilidades y competencias ling\u00fc\u00edsticas del idioma, teniendo como referencia los niveles de proficiencia establecidos en el Marco Com\u00fan Europeo de Referencia para las Lenguas (MCER). \r\n\r\nDado que los\/las estudiantes de PIBM desempe\u00f1ar\u00e1n los roles de mediador y de modelo ling\u00fc\u00edstico y cultural con sus estudiantes, estos\/as no solo deben mostrar una competencia apropiada en la lengua extranjera, sino que tambi\u00e9n deben ser un referente en el aula de ingl\u00e9s en t\u00e9rminos socioling\u00fc\u00edsticos, socioculturales y estrat\u00e9gicos. \r\n\r\nEs por ello que los equipos coordinadores de las asignaturas de Ingl\u00e9s Oral 1 y 3 y de Competencia Comunicativa 1 plantean la necesidad de dise\u00f1ar un plan de lectura espec\u00edfico y estrat\u00e9gico para la realidad de nuestra carrera. Este podr\u00e1 ser adem\u00e1s incorporado a las asignaturas que se orientan al desarrollo de estrategias de producci\u00f3n oral para comunicarse de forma competente en ingl\u00e9s (Ingl\u00e9s Oral 1-4 y Competencia Comunicativa Integrada 1-4). \r\n\r\nDicho esto, nuestra propuesta consiste en el dise\u00f1o de un plan de lectura, en una fase piloto, en el cual se considere la lectura no solo como una habilidad y destreza del lenguaje, sino que como una pr\u00e1ctica sociocultural. Al respecto, Quesada, Linares y Rivera (2017) sostienen que,\r\n \r\nla lectura constituye una pr\u00e1ctica sociocultural influida por determinantes sociales, econ\u00f3micas, pol\u00edticas y culturales. Es por ello que el estudio del fen\u00f3meno de la lectura \u0097desde cualquier perspectiva\u0097 requiere de una mirada multidimensional, pues \u00e9sta no ha sido una actividad est\u00e1tica, sino que ha estado vinculada a las necesidades de las \u00e9pocas, los cambios pol\u00edticos y sociales, la modificaci\u00f3n en la concepci\u00f3n de la educaci\u00f3n y otros aspectos que permiten identificar a la lectura como pr\u00e1ctica sociocultural (p.225).\r\n \r\nPor lo tanto, contar con un plan de lectura propio para PIBM, brindar\u00e1 a los y las estudiantes la oportunidad de acceder a textos que les permita ser capaces de abordar la lectura como una pr\u00e1ctica situada socioculturalmente, apreciar las similitudes y diferencias entre su cultura y otras, adem\u00e1s de fomentar las habilidades de pensamiento cr\u00edtico de los estudiantes de L2 y desarrollar y fortalecer sus habilidades avanzadas de lectura L2. \r\n\r\nLa propuesta contempla un plan piloto de lectura que consta de un ciclo de revisi\u00f3n de planes y programas, luego el dise\u00f1o, aplicaci\u00f3n y an\u00e1lisis de diagn\u00f3stico inicial, y posteriormente, el trabajo coordinado con una experta externa para la elaboraci\u00f3n del marco conceptual y operativo de dicho plan en la carrera.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2020 - Octubre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26711\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            La construcci\u00f3n del \u0091otro\u0092 en tiempos de pandemia:  un an\u00e1lisis de las representaciones de la migraci\u00f3n en medios de noticias digitales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26711\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26711\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Los medios de comunicaci\u00f3n son una de las principales fuentes de informaci\u00f3n y generaci\u00f3n de sentido (Baker, 2010). Estos producen la realidad social como experiencia colectiva y son la fuente de conocimiento m\u00e1s importante para las elites y sociedad civil en general (Ivanova & Jocelin, aceptado; Van Dijk, 1993; Ver\u00f3n, 1993). A trav\u00e9s de la (re)producci\u00f3n, construcci\u00f3n y legitimaci\u00f3n de creencias populares (Romero Lizama, 2011), tienen gran poder de influencia sobre la opini\u00f3n p\u00fablica (Van Dijk, 1993). Particularmente, los discursos y representaciones de la migraci\u00f3n privilegian voces hegem\u00f3nicas, siendo fuentes de aprendizaje de prejuicios y formas de discriminaci\u00f3n (Van Djik, 2006). Seg\u00fan G\u00f3mez y Torres (2020), en contextos de \u0093crisis\u0094 la imagen del migrante deviene particularmente controversial, siendo a menudo usada como \u0093chivo expiatorio\u0094 para explicar emergentes y persistentes problemas estructurales. Estos discursos y procesos de generaci\u00f3n de prejuicios no solo construyen significados. Tambi\u00e9n inciden en orientaciones sociales (de apertura o cierre) a la otredad (Vertovec & Wessendorf, 2010), en las percepciones intergrupales que est\u00e1n a la base de din\u00e1micas de conflicto y cohesi\u00f3n social (Figueiredo, Licata, Marambio, Garcia, y Rocha, 2020) y en las identidades de quienes son estigmatizados (Alexander, 2000).\r\nEstudiar la representaci\u00f3n de los migrantes durante la pandemia, nos permite reflexionar en c\u00f3mo los discursos del miedo cambian a trav\u00e9s del tiempo, y como la figura del migrante participa en ellos y en la construcci\u00f3n de la \u0091crisis\u0092 (Altheide, 2002; Chouliaraki & Stolic, 2017). En Chile existe un corpus de estudios creciente acerca de las representaciones de la migraci\u00f3n en medios de noticias, con un foco en prensa impresa (Brown y Romero 2010; Dammert & Erlandsen, 2020; Liberona, 2015; Poo, 2009) y, en menor medida, televisi\u00f3n (Ambiado & Fern\u00e1ndez, 2012) y medios digitales (Stefoni & Brito, 2019). En l\u00ednea con la literatura internacional, estos estudios destacan su representaci\u00f3n como amenaza, siendo com\u00fan su asociaci\u00f3n con problemas de criminalidad e ilegalidad (De Genova, 2013). Parafraseando a Browne, Silva, & Baessolo (2010, 86), en Chile la prensa suele crear generalizaciones, a trav\u00e9s de representaciones que f\u00e1cilmente mutan en prejuicios y estereotipos hacia el \u0093otro\u0094. \r\nDiscursos y representaciones de migrantes y minor\u00edas \u00e9tnicas no surgen en la nada, sino que tienen un car\u00e1cter situado. Aspectos como la econom\u00eda pol\u00edtica local y r\u00e9gimen migratorio nacional han demostrado ser cruciales (Husseini de Ara\u00fajo, 2020; cf. Stefoni & Brito, 2019). Adem\u00e1s, las representaciones de la migraci\u00f3n no son est\u00e1ticas. En la prensa chilena, por ejemplo, se han alineado con cambiantes agendas pol\u00edticas, pasando de \u0093discursos populistas punitivos\u0094 (foco en criminalidad y amenaza a la \u0093comunidad imaginada\u0094) (Dammert & Erlandsen, 2020), a la idea de regularizar para \u0093ordenar la casa\u0094, que presenta a la migraci\u00f3n como invasora de un lugar de pertenencia ajeno (Stefoni y Brito 2019). Este tipo de representaciones no necesariamente excluyen aquellas de victimizaci\u00f3n, compasi\u00f3n y adaptaci\u00f3n (Liberona, 2015; Maher & Elias, 2019); ambivalencias que requieren ser profundizadas en el contexto chileno.\r\nM\u00faltiples representaciones de personas migrantes pueden coexistir. Las categor\u00edas de etnicidad, g\u00e9nero, clase y estatus migratorio, entre otras, son distintamente articuladas en relaci\u00f3n con diferentes espacios y campos sociales (Anthias, 2002). Estudios recientes, por ejemplo, muestran que las mujeres migrantes y refugiadas suelen estar subrepresentadas en los medios, siendo m\u00e1s visibles junto a categor\u00edas religiosas y de clase (en tanto \u0093pobre\u0094) (Amores et al., 2020). Esta representaci\u00f3n de la otredad puede mitigar solidaridades de g\u00e9nero y clase (con no-migrantes), en torno a problem\u00e1ticas compartidas (L\u00fcnenborg & F\u00fcrsich, 2014). \r\nEn este contexto, nuestro estudio se pregunta \u00bfc\u00f3mo los medios de noticias digitales nacionales representan a la migraci\u00f3n en relaci\u00f3n con la crisis sanitaria generada por el COVID-19? \u00bfQu\u00e9 discursos y representaciones emergen a trav\u00e9s de la articulaci\u00f3n de diferentes categor\u00edas de diferencia y espacios sociales? Espec\u00edficamente, los objetivos son: 1) Analizar la representaci\u00f3n de la migraci\u00f3n a partir de la articulaci\u00f3n de distintas categor\u00edas de diferencia (ej.: g\u00e9nero, clase social, estatus migratorio, etnicidad u otras relativamente salientes); 2) Profundizar en la representaci\u00f3n del g\u00e9nero en noticias sobre migraci\u00f3n y pandemia. 3) Identificar los lugares y espacios de la migraci\u00f3n m\u00e1s com\u00fanmente representados y los significados construidos en torno a ellos; 4) Identificar los giros en la representaci\u00f3n de la migraci\u00f3n durante la pandemia; 5) Comparar las representaciones que hacen medios con distintas l\u00edneas editoriales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2020 - Enero 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Secretaria Regional Ministerial de las Culturas, las Artes y los Patrimonios de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26072\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26072\" aria-expanded=\"false\" aria-controls=\"collapse-26072\">\n                                            Estudio sobre Educaci\u00f3n Art\u00edstica en el Sistema Educativo Formal y no Formal de la regi\u00f3n del Libertador General Bernardo O\u0092Higgin Etapa I\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26072\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26072\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El presente estudio tiene como prop\u00f3sito realizar un levantamiento de datos actualizado sobre el estado de la Educaci\u00f3n Art\u00edstica en el sistema educativo formal, escuelas municipales, y espacios no formales de la Regi\u00f3n del Libertador Bernardo O\u0092Higgins. La muestra final ser\u00e1 de 100 escuelas b\u00e1sica municipales representativas de las tres provincias que componen la regi\u00f3n. \r\nEtapa I financiada por el fondo de Fortalecimiento de la Identidad Cultural Regional (FICR) por resoluci\u00f3n exenta N\u00ba  253[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ID16I10090<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2020 - Agosto 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26158\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Habilidades y Competencias para la Educaci\u00f3n Superior. Desarrollo de Instrumentos y Propuestas que aporten a un Nuevo Sistema de Admisi\u00f3n\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26158\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26158\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]FONDEF 2016 (proyecto n\u00ba ID16I10090, segunda etapa)\r\nHabilidades y Competencias para la Educaci\u00f3n Superior. Desarrollo de Instrumentos y Propuestas que aporten a un Nuevo Sistema de Admisi\u00f3n\r\nCargo: Investigadora Principal (Investigador responsable: Leonor Varas, UChile).\r\nSeptiembre 2020 \u0096 Agosto 2022[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2020 - Octubre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26247\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Laboratorio de diagn\u00f3stico Universidad de O\u0092Higgins ETAPA 2\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26247\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26247\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ER190042.<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2020 - Noviembre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>PAR EXPLORA O\u0092Higgins 2020<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26404\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26404\" aria-expanded=\"false\" aria-controls=\"collapse-26404\">\n                                            Producto de divulgaci\u00f3n cient\u00edfica ER190042: \u0093Artis y el Laberinto\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26404\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26404\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Desarrollo de libro infantil sobre bienestar.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ER190042.<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2020 - Noviembre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>PAR EXPLORA O\u0092Higgins 2020<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26553\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26553\" aria-expanded=\"false\" aria-controls=\"collapse-26553\">\n                                            Producto de divulgaci\u00f3n cient\u00edfica ER190042: \u0093Artis y el Laberinto\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26553\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26553\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Desarrollo de libro infantil sobre bienestar.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2020 - Marzo 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26664\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            El impacto de la pandemia por COVID-19 sobre las condiciones laborales y el bienestar psicosocial en Chile, desde una perspectiva de g\u00e9nero.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26664\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26664\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo general:\r\nAnalizar la relaci\u00f3n entre las condiciones laborales y de empleo, con el bienestar psicosocial durante la Pandemia por COVID-19 en Chile con perspectiva de g\u00e9nero.\r\nObjetivo(s) espec\u00edfico(s):\r\n- Caracterizar las modificaciones en las condiciones de empleo, trabajo y el bienestar psicosocial, seg\u00fan perspectiva de g\u00e9nero, durante la pandemia por COVID-19, en Chile y en la Regi\u00f3n de O'Higgins\r\n- Relacionar las condiciones de empleo y trabajo, y el bienestar psicosocial seg\u00fan perspectiva de[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2020 - Diciembre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26712\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            La representaci\u00f3n de la mujer migrante en la prensa escrita en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26712\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26712\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La presente propuesta se basa en el hecho que los medios de comunicaci\u00f3n tienen un papel significativo para definir la identidad social de los distintos colectivos sociales, incluso inmigrantes. \r\nEn Chile los inmigrantes son una minor\u00eda que representa 1.492.522  personas seg\u00fan el Informe T\u00e9cnico del Instituto Nacional de Estad\u00edstica en marzo 2020. Dentro de este grupo minoritario, las mujeres son la mitad, pero tienen poca voz y representatividad en los discursos p\u00fablicos, los que, junto con los medios de comunicaci\u00f3n refieren a este grupo social en t\u00e9rminos gen\u00e9ricos \u0093los inmigrantes\u0094. Como bien plantea Suarez Villegas (2013: 77): \u0093ser mujer constituye ya una posici\u00f3n de vulnerabilidad en la sociedad patriarcal, adem\u00e1s, ser inmigrante, constituye una doble vulnerabilidad, a la que cabr\u00eda a\u00f1adir una tercera derivada de su representaci\u00f3n en los medios de comunicaci\u00f3n\u0094.\r\nDicho esto, el presente proyecto constituye un estudio de car\u00e1cter exploratorio sobre las representaciones y las im\u00e1genes sociales que transmite la prensa chilena acerca de la mujer inmigrante. A trav\u00e9s del an\u00e1lisis cualitativo de las noticias aparecidas durante el periodo 2015-2019 en tres diarios nacionales (El Mercurio, Publimetro y La Tercera), se indaga en las tem\u00e1ticas y en las situaciones m\u00e1s relevantes en las que aparece asociada la imagen de la mujer inmigrante. \r\nLa presente propuesta nace a partir de los resultados preliminares del proyecto Fondecyt 11180178 \u0093El tratamiento informativo de los inmigrantes en la prensa nacional escrita actual (2015-2019) y su impacto en la opini\u00f3n p\u00fablica\u0094. Al recopilar el corpus de noticias y art\u00edculos sobre los inmigrantes publicados por tres peri\u00f3dicos nacionales chilenos (El Mercurio, La Tercera y Publimetro) durante los a\u00f1os 2015-2019, nos dimos cuenta que existe una cierta tendencia transversal de visualizar migraci\u00f3n en Chile a trav\u00e9s de ciertos grupos de personas. Es decir, predominan ciertos tipos de encuadres visuales (fotos) que acompa\u00f1an los art\u00edculos sobre inmigrantes y\/o inmigraci\u00f3n en Chile. Dentro de este corpus, hay un porcentaje no menor de los encuadres visuales de las mujeres inmigrantes. Cabe se\u00f1alar que  si bien es cierto, que a nivel textual, los peri\u00f3dicos no hablan directamente de las mujeres inmigrantes, s\u00ed, emplean sus im\u00e1genes para acompa\u00f1ar los art\u00edculos. \r\nDicho esto, el objetivo principal de este estudio es analizar la representaci\u00f3n visual de la mujer inmigrante en la prensa escrita en Chile. Es por esto, que nuestra investigaci\u00f3n tambi\u00e9n se yergue como un llamado al trato digno del migrante en los espacios informativos, lo que en Chile est\u00e1 normado (CNTV, 2017).\r\nLos resultados obtenidos a partir de este proyecto contribuir\u00e1n  al conocimiento del estado actual de la representaci\u00f3n de la mujer inmigrante en la prensa chilena.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26723\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Diferencias sexuales para adultos y ni\u00f1os en la adquisici\u00f3n y extinci\u00f3n de aprendizajes en un paradigma de aprendizaje predictivo.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26723\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26723\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2020 - Agosto 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26766\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Legitimidad de Carabineros: violencia, derechos humanos y control social\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26766\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26766\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El estallido social que remeci\u00f3 a Chile en octubre de 2019 trajo distintos tipos de fen\u00f3menos asociados al aumento de la violencia y el control social, tales como agresiones en contexto de protestas, saqueos y quema de estaciones de metro, entre otros. No obstante, la violencia ejercida por Carabineros durante las protestas es, quiz\u00e1s, lo m\u00e1s relevantes de considerar desde el punto de vista de los Derechos Humanos 1 . Estas situaciones han reducido la confianza hacia Carabineros a niveles hist\u00f3ricamente bajos en los \u00faltimos meses del a\u00f1o pasado (CEP, 2019) 2 . Casos emblem\u00e1ticos como el de Gustavo Gatica y Fabiola Campillay, as\u00ed como la investigaci\u00f3n interna hecha por Carabineros, han levantado muchas preguntas sobre el actuar de sus miembros, generando una crisis de legitimidad y un llamado a reestructurar esta instituci\u00f3n.\r\nAdicionalmente, la actual crisis socio-sanitaria generada por la pandemia del COVID-19, puede haber contribuido a aumentar esta percepci\u00f3n negativa de la instituci\u00f3n de Carabineros y de las autoridades en general. Durante los \u00faltimos meses se han establecido numerosas medidas de control social, como el toque de queda, que no han sido debidamente justificadas. A\u00fan m\u00e1s, las autoridades han aumentado las penas por incumplir las medidas de distancia social (como la cuarentena), sin tener en cuenta que determinados sectores sociales no adhieren a estas\r\nmedidas por razones socio-econ\u00f3micas que les impiden permanecer en sus casas. En resumen, en un contexto social que se empez\u00f3 a complejizar con el estallido social, la legitimidad con la que Carabineros es percibida se ha puesto en tela de juicio, debido tanto a los esc\u00e1ndalos internos, a las medidas de control social que han implementado, a la violencia ejercida y a las violaciones de los derechos humanos que han perpetrado. En este contexto, este proyecto pretende contribuir a la medici\u00f3n sistem\u00e1tica de la legitimidad de Carabineros en un contexto de crisis, tema que es clave desde el punto de vista del aseguramiento de la cohesi\u00f3n social.\r\n\r\nEn esta l\u00ednea, los objetivos de este proyecto son:\r\n- Evaluar las percepciones de legitimidad de Carabineros en la poblaci\u00f3n chilena, a lo largo del tiempo.\r\n- Examinar un modelo te\u00f3rico (escasamente aplicado en Chile) para explicar antecedentes y consecuencias de la legitimidad con la que se percibe a Carabineros.\r\n- Evaluar el efecto de las percepciones de justicia en el trato y los procedimientos utilizados por Carabineros al interactuar con la ciudadan\u00eda en la percepci\u00f3n de legitimidad de los mismos.\r\n- Evaluar el efecto de la percepci\u00f3n de legitimidad en (1) la justificaci\u00f3n de la violencia como forma de reivindicar derechos, (2) la tolerancia a la violencia estatal, (3) la aprobaci\u00f3n de medidas de control social represivo o punitivo, as\u00ed como de pol\u00edticas que reduzcan las libertades de las personas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2020 - Marzo 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26820\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            El impacto de la pandemia por COVID-19 sobre las condiciones laborales y el bienestar psicosocial en Chile, desde una perspectiva de g\u00e9nero.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26820\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26820\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo general:\r\nAnalizar la relaci\u00f3n entre las condiciones laborales y de empleo, con el bienestar psicosocial durante la Pandemia por COVID-19 en Chile con perspectiva de g\u00e9nero.\r\nObjetivo(s) espec\u00edfico(s):\r\n- Caracterizar las modificaciones en las condiciones de empleo, trabajo y el bienestar psicosocial, seg\u00fan perspectiva de g\u00e9nero, durante la pandemia por COVID-19, en Chile y en la Regi\u00f3n de O'Higgins\r\n- Relacionar las condiciones de empleo y trabajo, y el bienestar psicosocial seg\u00fan perspectiva de[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2020 - Enero 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26401\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Percepci\u00f3n sobre formas de discriminaci\u00f3n hacia personas de la diversidad sexo gen\u00e9rica en la Regi\u00f3n de O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26401\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26401\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El presente estudio nace de la evidencia que en Am\u00e9rica Latina a\u00fan persiste un conjunto de inequidades que afectan las relaciones de g\u00e9nero y que son sostenidas por las ideolog\u00edas del patriarcado y el heterosexismo (Barrientos, 2015). En particular, tanto el patriarcado como el heterosexismo favorecen un conjunto de condiciones adversas para quienes se definen como lesbianas, gays, bisexuales, transg\u00e9nero e intersexuales (en adelante, LGBTI;Barrientos, 2015;\r\nHerek, 2000) y promueven un modelo binario del g\u00e9nero (masculino o femenino; McCann & Sharek, 2016). Entre todas las condiciones g\u00e9nero-diversas, la poblaci\u00f3n Transg\u00e9nero, entendiendo por tal a aquellas personas cuya identidad de g\u00e9nero o la expresi\u00f3n de \u00e9ste difiere de lo esperado culturalmente una vez que se ha hecho la asignaci\u00f3n de sexo al nacer como hombre o mujer (Davidson, 2007; Valentine, 2007), aparece como la m\u00e1s expuesta a estigma, violencia, prejuicio, social , inequidad y discriminaci\u00f3n en todo \u00e1mbito lo que redunda en un marcado deterioro de sus indicadores de calidad bienestar psicosocial.\r\nDe acuerdo con datos recopilados para la conmemoraci\u00f3n de la Memoria Trans la situaci\u00f3n de transfobia y de violencia hacia la poblaci\u00f3n trans en Sudam\u00e9rica es alarmante, estableci\u00e9ndose como el continente con mayor tasa de mortalidad asociada a cr\u00edmenes de odio. Si bien esta situaci\u00f3n no es exclusiva de nuestro continente, en pa\u00edses donde existen legislaciones que protegen a poblaciones que culturalmente no pueden ser encasilladas como \u0093tradicionales\u0094 muestran tasas de violencia relativamente menores (Transmurder Monitoring, 2018). La soluci\u00f3n a la violencia de g\u00e9nero como un eje, se relaciona fundamentalmente con la capacidad de realizar cambios estructurales en las pol\u00edticas de estado tendientes a propiciar cambios culturales que eviten la segregaci\u00f3n de la poblaci\u00f3n Trans y que \u00e9stas est\u00e9n sustentadas en evidencia constituyendo un discurso s\u00f3lido y un constructo social para la toma de decisiones. Sin embargo, y pese a que en los \u00faltimos a\u00f1os ha aumentado el debate p\u00fablico sobre las personas trans (Halberstam, 2018; Stryker, 2017), lo que ha estimulado el surgimiento de un campo de discusi\u00f3n, investigaci\u00f3n y trabajo para las ciencias sociales y para\r\nla psicolog\u00eda en particular, en Chile la investigaci\u00f3n al respecto es reciente y la informaci\u00f3n\r\n\r\n manejada es incompleta y mayoritariamente no sistem\u00e1tica en especial en regiones, como el caso de Rancagua donde esta es b\u00e1sicamente inexistente.\r\nEl objetivo operacional del estudio es entonces es desarrollar una investigaci\u00f3n exploratoria \/descriptiva, cuanti-cualitativa sistem\u00e1tica en un colectivo Trans organizado (OTR) que abarca la ciudad de Rancagua y alrededores donde podamos recoger informaci\u00f3n extensiva para la caracterizaci\u00f3n sociodemogr\u00e1fica, econ\u00f3mica de los participantes, indicadores de salud f\u00edsica y mental y por otra parte realizar un trabajo cualitativo de tipo narrativo-biogr\u00e1fico con los mismos. De esta manera se pretende acercarnos a \u0093significar\u0094 y \u0093explicar\u0094 la vivencia y las caracter\u00edsticas de comportamiento de las personas transg\u00e9nero de nuestra localidad que las cifras en ocasiones no permiten transparentar. Si bien el aporte en t\u00e9rminos de ampliaci\u00f3n del conocimiento sistem\u00e1tico es uno de los objetivos primarios de la investigaci\u00f3n, tambi\u00e9n consideramos central la posibilidad de contribuir a la sensibilizaci\u00f3n social y de las instancias de gobierno local a trav\u00e9s de informaci\u00f3n objetiva que promueva el mejoramiento de los derechos y calidad de vida de los participantes y poblaci\u00f3n transg\u00e9nero en general.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2020 - Febrero 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26402\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Personas Transg\u00e9nero en Rancagua: estudio exploratorio cuanti-cualitativo de sus historias de vida y bienestar psico-social\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26402\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26402\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En Chile, la realidad de las personas que se identifican como g\u00e9nero diversas (es decir, no adscriben a la concepci\u00f3n de g\u00e9nero binaria tradicional) ha experimentado cambios en las \u00faltimas d\u00e9cadas con el paulatino reconocimiento de derechos, incremento relativo de la aceptaci\u00f3n social, mayor visibilizaci\u00f3n, etc. Sin embargo, existen estereotipos, prejuicios y creencias arraigadas socialmente que favorecen la permanencia de actitudes y conductas discriminatorias y\/o f\u00f3bicas en distintos \u00e1mbitos sociales. Se ha mostrado que uno de los pilares de las estrategias orientadas a promover, sensibilizar y concientizar en torno al respeto por la diversidad de g\u00e9nero radica en la producci\u00f3n de conocimiento sistem\u00e1tico en torno a la realidad nacional, regional y local que permita la contextualizaci\u00f3n y visibilizaci\u00f3n de las situaciones vitales de las personas y el abordaje desde la acci\u00f3n institucional educativa, de salud, gesti\u00f3n comunitaria, entre otras. Si bien en Chile se han realizado encuestas y se intentan elaborar indicadores para caracterizar el n\u00famero, calidad de vida y tambi\u00e9n actitudes f\u00f3bicas y experiencias de discriminaci\u00f3n en diversos colectivos pertenecientes a la diversidad de g\u00e9nero, por razones de alcance y metodol\u00f3gicas todav\u00eda no son lo suficientemente precisas. En este sentido, en nuestra regi\u00f3n en particular, se verifica un d\u00e9ficit de informaci\u00f3n en torno a la visibilizaci\u00f3n de la diversidad como tambi\u00e9n la presencia de actitudes y pr\u00e1cticas discriminatorias no asumidas ni problematizadas socialmente. Por este motivo, este estudio tiene por finalidad ampliar el conocimiento acerca de las opiniones, valores, comportamientos y actitudes ante la diversidad sexo-gen\u00e9rica en la Regi\u00f3n del Lib.Gral.Bdo. O\u0092Higgins en distintos \u00e1mbitos sociales e institucionales desde una doble perspectiva, cuanti-cualitiva que permitir\u00e1 obtener indicadores objetivos sobre esta realidad y a\r\nsu vez generar un documento audiovisual que permita la socializaci\u00f3n masiva de estos hallazgos, enriquecidos con una exploraci\u00f3n cualitativa de corte biogr\u00e1fico.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2020 - Febrero 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de O'Higgins<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26434\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Personas Transg\u00e9nero en Rancagua: estudio exploratorio cuanti-cualitativo de sus historias de vida y bienestar psico-social\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26434\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26434\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En Chile, la realidad de las personas que se identifican como g\u00e9nero diversas (es decir, no adscriben a la concepci\u00f3n de g\u00e9nero binaria tradicional) ha experimentado cambios en las \u00faltimas d\u00e9cadas con el paulatino reconocimiento de derechos, incremento relativo de la aceptaci\u00f3n social, mayor visibilizaci\u00f3n, etc. Sin embargo, existen estereotipos, prejuicios y creencias arraigadas socialmente que favorecen la permanencia de actitudes y conductas discriminatorias y\/o f\u00f3bicas en distintos \u00e1mbitos sociales. Se ha mostrado que uno de los pilares de las estrategias orientadas a promover, sensibilizar y concientizar en torno al respeto por la diversidad de g\u00e9nero radica en la producci\u00f3n de conocimiento sistem\u00e1tico en torno a la realidad nacional, regional y local que permita la contextualizaci\u00f3n y visibilizaci\u00f3n de las situaciones vitales de las personas y el abordaje desde la acci\u00f3n institucional educativa, de salud, gesti\u00f3n comunitaria, entre otras. Si bien en Chile se han realizado encuestas y se intentan elaborar indicadores para caracterizar el n\u00famero, calidad de vida y tambi\u00e9n actitudes f\u00f3bicas y experiencias de discriminaci\u00f3n en diversos colectivos pertenecientes a la diversidad de g\u00e9nero, por razones de alcance y metodol\u00f3gicas todav\u00eda no son lo suficientemente precisas. En este sentido, en nuestra regi\u00f3n en particular, se verifica un d\u00e9ficit de informaci\u00f3n en torno a la visibilizaci\u00f3n de la diversidad como tambi\u00e9n la presencia de actitudes y pr\u00e1cticas discriminatorias no asumidas ni problematizadas socialmente. Por este motivo, este estudio tiene por finalidad ampliar el conocimiento acerca de las opiniones, valores, comportamientos y actitudes ante la diversidad sexo-gen\u00e9rica en la Regi\u00f3n del Lib.Gral.Bdo. O\u0092Higgins en distintos \u00e1mbitos sociales e institucionales desde una doble perspectiva, cuanti-cualitiva que permitir\u00e1 obtener indicadores objetivos sobre esta realidad y a\r\nsu vez generar un documento audiovisual que permita la socializaci\u00f3n masiva de estos hallazgos, enriquecidos con una exploraci\u00f3n cualitativa de corte biogr\u00e1fico.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26017\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Cognici\u00f3n matem\u00e1tica y metodolog\u00eda de c\u00e1lculo Abierto Basado en N\u00fameros en el 3er Ciclo de Educaci\u00f3n Primaria\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26017\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26017\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetivo central de este proyecto es desarrollar nuevos enfoques experimentales para:\r\n(1) conocer las funciones cognitivas involucradas en el aprendizaje matem\u00e1tico: (2) implementar un programa de aprendizaje de matem\u00e1ticas utilizando el innovador enfoque de \"Algoritmo abierto basado en n\u00fameros\" (ABN); (3) Seguimiento de los alumnos\/as de 5o y 6o curso, que han aprendido matem\u00e1ticas con el m\u00e9todo ABN y el pr\u00f3ximo a\u00f1o iniciar\u00e1n la Educaci\u00f3n Secundaria Obligatoria, donde el m\u00e9todo ABN est\u00e1 menos implantado. El m\u00e9todo ABN constituye un profundo cambio conceptual en la ense\u00f1anza de las matem\u00e1ticas, que desarrolla un sentido num\u00e9rico centrado en n\u00fameros en lugar de en cifras. Esta investigaci\u00f3n solo puede alcanzar su objetivo mediante el uso de una metodolog\u00eda compleja: dise\u00f1o experimental con grupos de control, programa de capacitaci\u00f3n espec\u00edfica de alta calidad para maestros, y seguimiento apropiado de los estudiantes que har\u00e1n la transici\u00f3n a la ESO. Los participantes aprenden matem\u00e1ticas a trav\u00e9s del m\u00e9todo ABN con un enfoque relacionado con la potenciaci\u00f3n tambi\u00e9n de sus funciones cognitivas. Nuestra hip\u00f3tesis es que los ni\u00f1os en riesgo de dificultades de aprendizaje matem\u00e1tico organizan sus funciones ejecutivas de manera inapropiada. El proyecto tiene la intenci\u00f3n de desarrollar un m\u00e9todo de entrenamiento ABN espec\u00edfico que ayudar\u00e1 a los estudiantes a reconstruir la arquitectura cognitiva necesaria para la adquisici\u00f3n de los contenidos matem\u00e1ticos. El proyecto ABN tendr\u00e1 un impacto en la comprensi\u00f3n actual sobre c\u00f3mo los mecanismos cognitivos generales y espec\u00edficos que limitan la forma en que los alumnos\/as abordan\r\nla tarea de aprendizaje matem\u00e1tico. Este es un tema multidisciplinar muy relevante para los investigadores en psicolog\u00eda, matem\u00e1ticas y educaci\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> INV 002<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2020 - Mayo 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26214\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Apoyo a la investigaci\u00f3n en ciencias de la educaci\u00f3n\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26214\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26214\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Predictores socioecon\u00f3micos y psicobiol\u00f3gicos del desempe\u00f1o acad\u00e9mico en estudiantes\r\nde primer a\u00f1o de pedagog\u00eda de la UOH (Programa de Formaci\u00f3n Inicial Docente)\r\n\r\nCl\u00e1sicamente se ha descrito que el rendimiento durante la ense\u00f1anza media de los estudiantes en Chile\r\na trav\u00e9s del NEM y sus resultados en las pruebas de ingreso a la universidad, adem\u00e1s un factor\r\ndeterminando son las condiciones socioecon\u00f3micas, que resultan ser un factor predictivo de\r\nrendimiento acad\u00e9mico durante los primeros a\u00f1os de educaci\u00f3n universitaria. Paralelamente, se ha\r\nconstatado que los estudiantes a lo largo del primer semestre en la universidad sufren un deterioro en\r\nsu calidad del sue\u00f1o y en los h\u00e1bitos alimenticios, todo relacionado con un aumento de sus niveles de\r\nestr\u00e9s. Por otro lado, hipotetizamos una asociaci\u00f3n de estos indicadores con el desempe\u00f1o en pruebas\r\nde memoria de trabajo, y pueden ser elementos predictivos que determinen el desempe\u00f1o acad\u00e9mico.\r\nNuestra investigaci\u00f3n tiene por objetivo estudiar ciertos indicadores de higiene, tales como sue\u00f1o,\r\nestr\u00e9s y alimentaci\u00f3n, con el fin de predecir su importancia en la predicci\u00f3n del desempe\u00f1o\r\nacad\u00e9mico. Contemplamos el uso de datos anonimizados en acuerdo con lo que establezca el comit\u00e9\r\nde \u00e9tica institucional. En el caso espec\u00edfico de estudiantes de educaci\u00f3n b\u00e1sica y educaci\u00f3n especial,\r\ndeterminar los principales factores que afectan el rendimiento acad\u00e9mico, es una herramienta \u00fatil que\r\ncreemos permitir\u00e1 modificar ciertos modelos con el fin de mejorar los procesos de ense\u00f1anza \u0096\r\naprendizaje. Este estudio se enmarca en un proyecto de Fortalecimiento a la formaci\u00f3n Inicial\r\nDocente el cual apoyar\u00e1 con los fondos necesarios para el buen desarrollo de esta investigaci\u00f3n. La\r\ncontribuci\u00f3n institucional de la UOH se limita a autorizar la participaci\u00f3n voluntaria de sus\r\nestudiantes, que se formalizar\u00e1 a trav\u00e9s de la firma del consentimiento informado por cada uno de los\r\nestudiantes de forma voluntaria sin mediar recompensa ni perjuicio fruto de su decisi\u00f3n de colaborar\r\nen el estudio. A los estudiantes de pedagog\u00eda que voluntariamente decidan participar, se les aplicar\u00e1,\r\nal inicio y al final del presente semestre acad\u00e9mico, una encuesta online que evaluar\u00e1 diferentes\r\nmarcadores de estr\u00e9s y mediante el uso de una aplicaci\u00f3n, se recopilar\u00e1 informaci\u00f3n aleatorizada de\r\nsus h\u00e1bitos de alimentaci\u00f3n y de descanso. Estos datos ser\u00e1n analizados considerando elementos de\r\nrendimiento en la educaci\u00f3n media y marcadores socioecon\u00f3micos. Junto con esto, al finalizar el\r\nsemestre, siempre con el consentimiento de cada participante, se solicitar\u00e1 al docente responsable del\r\ncurso las calificaciones y nota final de todos ellos. Estos datos ser\u00e1n analizados cuantitativamente y de\r\nforma anonimizada. Finalmente se evaluar\u00e1n todos los marcadores obtenidos, realizando un an\u00e1lisis\r\ncuantitativo y cualitativo, combinando m\u00e9todos univariados y multivariados para evaluar estos de\r\nmanera exploratoria e inferencial. Posteriormente proponemos dar punto final al estudio realizando un\r\nan\u00e1lisis profundo del efecto de los diferentes componentes a trav\u00e9s de la t\u00e9cnica de PCA.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> INV 002<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2020 - Mayo 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26418\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Apoyo a la investigaci\u00f3n en ciencias de la educaci\u00f3n\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26418\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26418\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Predictores socioecon\u00f3micos y psicobiol\u00f3gicos del desempe\u00f1o acad\u00e9mico en estudiantes\r\nde primer a\u00f1o de pedagog\u00eda de la UOH (Programa de Formaci\u00f3n Inicial Docente)\r\n\r\nCl\u00e1sicamente se ha descrito que el rendimiento durante la ense\u00f1anza media de los estudiantes en Chile\r\na trav\u00e9s del NEM y sus resultados en las pruebas de ingreso a la universidad, adem\u00e1s un factor\r\ndeterminando son las condiciones socioecon\u00f3micas, que resultan ser un factor predictivo de\r\nrendimiento acad\u00e9mico durante los primeros a\u00f1os de educaci\u00f3n universitaria. Paralelamente, se ha\r\nconstatado que los estudiantes a lo largo del primer semestre en la universidad sufren un deterioro en\r\nsu calidad del sue\u00f1o y en los h\u00e1bitos alimenticios, todo relacionado con un aumento de sus niveles de\r\nestr\u00e9s. Por otro lado, hipotetizamos una asociaci\u00f3n de estos indicadores con el desempe\u00f1o en pruebas\r\nde memoria de trabajo, y pueden ser elementos predictivos que determinen el desempe\u00f1o acad\u00e9mico.\r\nNuestra investigaci\u00f3n tiene por objetivo estudiar ciertos indicadores de higiene, tales como sue\u00f1o,\r\nestr\u00e9s y alimentaci\u00f3n, con el fin de predecir su importancia en la predicci\u00f3n del desempe\u00f1o\r\nacad\u00e9mico. Contemplamos el uso de datos anonimizados en acuerdo con lo que establezca el comit\u00e9\r\nde \u00e9tica institucional. En el caso espec\u00edfico de estudiantes de educaci\u00f3n b\u00e1sica y educaci\u00f3n especial,\r\ndeterminar los principales factores que afectan el rendimiento acad\u00e9mico, es una herramienta \u00fatil que\r\ncreemos permitir\u00e1 modificar ciertos modelos con el fin de mejorar los procesos de ense\u00f1anza \u0096\r\naprendizaje. Este estudio se enmarca en un proyecto de Fortalecimiento a la formaci\u00f3n Inicial\r\nDocente el cual apoyar\u00e1 con los fondos necesarios para el buen desarrollo de esta investigaci\u00f3n. La\r\ncontribuci\u00f3n institucional de la UOH se limita a autorizar la participaci\u00f3n voluntaria de sus\r\nestudiantes, que se formalizar\u00e1 a trav\u00e9s de la firma del consentimiento informado por cada uno de los\r\nestudiantes de forma voluntaria sin mediar recompensa ni perjuicio fruto de su decisi\u00f3n de colaborar\r\nen el estudio. A los estudiantes de pedagog\u00eda que voluntariamente decidan participar, se les aplicar\u00e1,\r\nal inicio y al final del presente semestre acad\u00e9mico, una encuesta online que evaluar\u00e1 diferentes\r\nmarcadores de estr\u00e9s y mediante el uso de una aplicaci\u00f3n, se recopilar\u00e1 informaci\u00f3n aleatorizada de\r\nsus h\u00e1bitos de alimentaci\u00f3n y de descanso. Estos datos ser\u00e1n analizados considerando elementos de\r\nrendimiento en la educaci\u00f3n media y marcadores socioecon\u00f3micos. Junto con esto, al finalizar el\r\nsemestre, siempre con el consentimiento de cada participante, se solicitar\u00e1 al docente responsable del\r\ncurso las calificaciones y nota final de todos ellos. Estos datos ser\u00e1n analizados cuantitativamente y de\r\nforma anonimizada. Finalmente se evaluar\u00e1n todos los marcadores obtenidos, realizando un an\u00e1lisis\r\ncuantitativo y cualitativo, combinando m\u00e9todos univariados y multivariados para evaluar estos de\r\nmanera exploratoria e inferencial. Posteriormente proponemos dar punto final al estudio realizando un\r\nan\u00e1lisis profundo del efecto de los diferentes componentes a trav\u00e9s de la t\u00e9cnica de PCA.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2020 - Marzo 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25974\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estudio epidemiol\u00f3gico observacional para evaluar el efecto de medidas de control gubernamentales sobre la din\u00e1mica espacio-temporal de Covid-19 en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25974\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25974\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]A\u00fan lejos de tener una vacuna efectiva y segura, los gobiernos nacionales han tenido que establecer medidas sanitarias (e.g. cuarentena) para reducir el impacto de la pandemia de COVID-19. Sin embargo, no existe claridad respecto a cu\u00e1les medidas son las m\u00e1s eficaces y c\u00f3mo la efectividad de \u00e9stas es afectada por diferentes contextos sociales, demogr\u00e1ficos y epidemiol\u00f3gicos. El objetivo de esta propuesta es desarrollar un estudio observacional para evaluar el impacto de las diferentes medidas de control aplicadas por la autoridad sanitaria sobre la din\u00e1mica de COVID-19, a nivel comunal y de \u00e1reas metropolitanas, utilizando la informaci\u00f3n generada por el Ministerio de Salud. Los datos ser\u00e1n analizados utilizando modelos de regresi\u00f3n para datos de conteo, lo que permitir\u00e1 evaluar potenciales desfases en el tiempo de los efectos de las medidas de control, junto con considerar el efecto de variables potencialmente confundentes. Al finalizar este estudio, la autoridad sanitaria dispondr\u00e1 de evidencia cient\u00edfica para sustentar el establecimiento de diferentes medidas de control para COVID-19, dependiendo de contextos sociales, demogr\u00e1ficos y epidemiol\u00f3gicos, permitiendo enfatizar aquellas medidas m\u00e1s adecuadas para cada caso. Los modelos quedar\u00e1n disponibles en una aplicaci\u00f3n web donde podr\u00e1n ser interrogados por las autoridades sanitarias.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2020 - Marzo 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26300\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estudio epidemiol\u00f3gico observacional para evaluar el efecto de medidas de control gubernamentales sobre la din\u00e1mica espacio-temporal de Covid-19 en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26300\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26300\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]A\u00fan lejos de tener una vacuna efectiva y segura, los gobiernos nacionales han tenido que establecer medidas sanitarias (e.g. cuarentena) para reducir el impacto de la pandemia de COVID-19. Sin embargo, no existe claridad respecto a cu\u00e1les medidas son las m\u00e1s eficaces y c\u00f3mo la efectividad de \u00e9stas es afectada por diferentes contextos sociales, demogr\u00e1ficos y epidemiol\u00f3gicos. El objetivo de esta propuesta es desarrollar un estudio observacional para evaluar el impacto de las diferentes medidas de control aplicadas por la autoridad sanitaria sobre la din\u00e1mica de COVID-19, a nivel comunal y de \u00e1reas metropolitanas, utilizando la informaci\u00f3n generada por el Ministerio de Salud. Los datos ser\u00e1n analizados utilizando modelos de regresi\u00f3n para datos de conteo, lo que permitir\u00e1 evaluar potenciales desfases en el tiempo de los efectos de las medidas de control, junto con considerar el efecto de variables potencialmente confundentes. Al finalizar este estudio, la autoridad sanitaria dispondr\u00e1 de evidencia cient\u00edfica para sustentar el establecimiento de diferentes medidas de control para COVID-19, dependiendo de contextos sociales, demogr\u00e1ficos y epidemiol\u00f3gicos, permitiendo enfatizar aquellas medidas m\u00e1s adecuadas para cada caso. Los modelos quedar\u00e1n disponibles en una aplicaci\u00f3n web donde podr\u00e1n ser interrogados por las autoridades sanitarias.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2020 - Marzo 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26422\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estudio epidemiol\u00f3gico observacional para evaluar el efecto de medidas de control gubernamentales sobre la din\u00e1mica espacio-temporal de Covid-19 en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26422\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26422\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]A\u00fan lejos de tener una vacuna efectiva y segura, los gobiernos nacionales han tenido que establecer medidas sanitarias (e.g. cuarentena) para reducir el impacto de la pandemia de COVID-19. Sin embargo, no existe claridad respecto a cu\u00e1les medidas son las m\u00e1s eficaces y c\u00f3mo la efectividad de \u00e9stas es afectada por diferentes contextos sociales, demogr\u00e1ficos y epidemiol\u00f3gicos. El objetivo de esta propuesta es desarrollar un estudio observacional para evaluar el impacto de las diferentes medidas de control aplicadas por la autoridad sanitaria sobre la din\u00e1mica de COVID-19, a nivel comunal y de \u00e1reas metropolitanas, utilizando la informaci\u00f3n generada por el Ministerio de Salud. Los datos ser\u00e1n analizados utilizando modelos de regresi\u00f3n para datos de conteo, lo que permitir\u00e1 evaluar potenciales desfases en el tiempo de los efectos de las medidas de control, junto con considerar el efecto de variables potencialmente confundentes. Al finalizar este estudio, la autoridad sanitaria dispondr\u00e1 de evidencia cient\u00edfica para sustentar el establecimiento de diferentes medidas de control para COVID-19, dependiendo de contextos sociales, demogr\u00e1ficos y epidemiol\u00f3gicos, permitiendo enfatizar aquellas medidas m\u00e1s adecuadas para cada caso. Los modelos quedar\u00e1n disponibles en una aplicaci\u00f3n web donde podr\u00e1n ser interrogados por las autoridades sanitarias.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2020 - Junio 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26117\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            II190105 &#8211; Estudio de los mecanismos biomec\u00e1nicos activados por hipoxia a nivel del endotelio vascular\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26117\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26117\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las enfermedades cardiovasculares (ECV), incluidas la hipertensi\u00f3n, el accidente cerebrovascular y la enfermedad de las arterias coronarias, son las principales patolog\u00edas a nivel mundial con un impacto significativo en la morbilidad y la mortalidad. El riesgo de enfermedades cardiovasculares se explica parcialmente por factores gen\u00e9ticos, pero en mayor medida por est\u00edmulos que tienen lugar durante el desarrollo temprano y el envejecimiento. La funci\u00f3n vascular durante la vida est\u00e1 determinada principalmente por tensiones mec\u00e1nicas resultantes de la presi\u00f3n sangu\u00ednea y el flujo, as\u00ed como por v\u00edas de se\u00f1alizaci\u00f3n activadas por la disponibilidad de ox\u00edgeno. En este contexto, alteraciones en las fuerzas de estiramiento (i.e. tensiones residuales circunferenciales y longitudinales de las arterias), la tensi\u00f3n de corte anormal (shear stress i.e: la fricci\u00f3n del flujo sangu\u00edneo en la superficie arterial luminal) y la hipoxia (i.e. la disminuci\u00f3n relativa de las presiones de ox\u00edgeno) son factores cr\u00edticos en el desarrollo de ECV. \r\nLos miembros de este proyecto se han centrado en \u00e1reas particulares de estos procesos, sin embargo, se requieren esfuerzos adicionales interdisciplinarios para entender de manera integral los mecanismos mec\u00e1nicos y moleculares involucrados en los or\u00edgenes de la disfunci\u00f3n cardiovascular. Recientemente se ha descrito a PIEZO1, un canal de cationes no selectivo, como uno de los principales activadores de la relajaci\u00f3n dependiente de endotelio en respuesta a la tensi\u00f3n de corte. Sin embargo, la regulaci\u00f3n de \u00e9ste, por parte de los est\u00edmulos descritos anteriormente, no ha sido a\u00fan explorada. La presente propuesta busca caracterizar, a trav\u00e9s de un estudio con enfoques en biomec\u00e1nica, fisiolog\u00eda y biolog\u00eda molecular, los cambios en la funci\u00f3n del mecano-sensor PIEZO1, en respuesta a est\u00edmulos f\u00edsicos y biol\u00f3gicos en c\u00e9lulas endoteliales de arteria umbilical humana, con el fin de identificar potenciales blancos de modulaci\u00f3n de la funci\u00f3n vascular en condiciones que promueven las ECV.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2020 - Agosto 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26246\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Laboratorio de diagn\u00f3stico Universidad de O\u0092Higgins. ETAPA 1\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26246\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26246\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2020 - Noviembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26290\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortalecimiento de las capacidades estrat\u00e9gicas, docentes, de investigaci\u00f3n y de vinculaci\u00f3n de la Universidad de O\u0092higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26290\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26290\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo espec\u00edfico N\u00b06: Implementar la primera fase de un Observatorio del Medio Ambiente de la Regi\u00f3n de O\u0092Higgins.\r\nEstrategias asociadas al objetivo espec\u00edfico N\u00b06: \r\n- Impulsar el dise\u00f1o e implementaci\u00f3n del Observatorio del Medio Ambiente en su primera fase (Atm\u00f3sfera) como complemento del centro de an\u00e1lisis qu\u00edmico y biol\u00f3gico, resultante del proceso de instalaci\u00f3n de la unidad de an\u00e1lisis\r\n- constituir un repositorio de informaci\u00f3n ambiental y en unidades de captura de datos e informaci\u00f3n a nivel regional.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2020 - Junio 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26372\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            VIGILANCIA ACTIVA MEDIANTE DIAGN\u00d3STICO MOLECULAR DE SARS-COV-2 EN POTENCIALES RESERVORIOS SILVESTRES\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26372\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26372\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En esta pandemia causada por el virus SARS-CoV-2, nos cuestionamos si ciertas especies de fauna se transformar\u00e1n en reservorios del virus en nuestro pa\u00eds. L\u00ednea base: Se ha detectado positividad en felinos dom\u00e9sticos (Shi y col. 2020, Science eabb7015) y en zool\u00f3gicos, sugiriendo exposici\u00f3n de las especies nativas, especialmente al incursionar en sectores urbanos, donde la exposici\u00f3n al virus es mayor. Ademas, se ha reportado enfermedad respiratoria causada por SARS-CoV-2 en granjas de visones en Europa, con la consiguiente diseminaci\u00f3n del virus a los humanos (Oude Munnink y Col. 2020, Science abe5901). Por otra parte, en murci\u00e9lagos y roedores se describe infecci\u00f3n por distintos virus (Luis y col. 2013 Proc. Biol. Sci. 280: 20122753). Algunas especies tienen un h\u00e1bitat estrechamente relacionado a las viviendas, lo que facilita que exista spill-over (\u0093derrame\u0094 de pat\u00f3genos) hacia la poblaci\u00f3n humana; en este caso, dado que son las personas quienes portan el virus en Chile, podr\u00eda ocurrir spill-back (retorno de los pat\u00f3genos a los animales o zoonosis reversa) (Daszak y col. 2000, Science 287: 443-449). Las consecuencias en animales silvestres a\u00fan no se han investigado en profundidad; podr\u00edan ser nefastas si provoca cuadros cl\u00ednicos debilitantes o mortalidad. En especies consideradas plaga, su infecci\u00f3n constituir\u00eda un riesgo inminente de diseminaci\u00f3n a la poblaci\u00f3n. Con la informaci\u00f3n a obtener, se podr\u00e1n establecer protocolos de manejo, difusi\u00f3n y prevenci\u00f3n comunitaria para proteger a la biodiversidad y a la poblaci\u00f3n chilena.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2020 - Diciembre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26667\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Identification of Causes, Reasons And Solutions for High COVID-19 mortality rate in AGEd populations (CRASH CAGE)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26667\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26667\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The epidemiology of the coronavirus disease 2019 (COVID-19) have revealed a dramatic\r\nmortality rate in older age groups. Notably, a similar epidemiological pattern was reported with other emerging infections and zoonosis. Further observations have however highlighted substantial differences between countries. By this project, we want to decipher social, epidemiological and biological causes of differences in COVID-19 mortality rates across countries and age groups, convinced that findings may be relevant also for future emerging infection and other zoonosis.\r\nTo this aim, we will first embark in an epidemiological analysis to understand sociodemographic factors associated with higher mortality rates. In parallel, we will characterize potential defects in mounting SARS-CoV-2 specific adaptive cellular responses in most-at-risk population (elderly and frail subjects).\r\nThese two activities will provide important clues to plan preventive strategies. Indeed,\r\npreliminary results suggest that molecules able to normalize lipid metabolism (which is altered in subjects susceptible to COVID-19) may restore T-cell functionality in the elderly. These molecules will be assessed, in vitro, for their capacity boost CD8+ T cell priming against SARS-CoV-2 in elderly and frail individuals. It is important to note that the effectiveness of preventive measures is strictly related to their compliance and, to this aim, proper communication measures are requested. These will be the focus of our IV activity.\r\nElderly and frail subjects constitute a population which should be proactively targeted in\r\npreventive strategies against second waves of COVID-19 but also against outbreaks of future\/new emerging infections and zoonosis.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2020 - Diciembre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26668\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Modern Design &#038; Interactive Teaching Methods, MoDITeM for virtual training\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26668\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26668\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]At present the planet is facing a global disease caused by COVID-19, that has been classified as a pandemic by the World Health Organization (WHO). In this exceptional context, WHO recommends quarantine and social distance for reduce spreading, diseases and deaths among the population.1 One of the main effects of these measures is the interruption of classes at schools, colleges and universities, with students at home.1 The impossibility of presential classes interrupted the educational and communication processes, that are very important in this situation of uncertainty, lack of information and fake news.2 For that reason, technology and virtual education are essentials for adaptive learning and also a new way to access from everywhere through mobile devices.3 Nevertheless, it could imply improvisation with a lot of trial and error, increasing inequality between students that could afford a better education and those who not.4 \r\nOn the other hand, implications beyond the healthcare domain - which have placed global sustainable development under threat - highlight the need for the One Health transdisciplinary approach5,6 to tackle the situation7. However, the integration of different disciplines is still a challenge for global health.6 Therefore, capacity building among students in this direction should be promoted.8\r\nWithin this scenario, this pilot course on Modern Design & Interactive Teaching Methods, MoDITeM is designed under the train-the-trainers concept to provide educators in the field of health and other disciplines a methodological framework and didactic teaching methods to develop their own virtual teaching. Teaching methods will promote inter-professional and transdisciplinary learning.  Thus, we will contribute to cope not only with challenges in this abrupt change to virtual education for the isolated student population in Covid's quarantine, but also to promote the search for comprehensive solutions to local problems in the future.\r\nThe pilot project will be implemented in partner universities in three Latin American countries and one African country, strengthening the South-South collaboration network.  Also, it will permit to reach people far away from main cities, improving the socialization of knowledge and equal opportunities for the population. It will allow to improve skills in teaching methods, research communication and sharing knowledge with peers in an LA and African settings, spreading the OH approach and its sustainability.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2020 - Diciembre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26670\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            One Health Knowledge Caf\u00e9\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26670\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26670\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Virtual learning and networking is an effective approach to develop and build on scientific knowledge and professional skills. In 2020, the global community is affected by Coronavirus Disease (COVID-19) limiting people\u0092s ability to travel and meet face to face due to the pandemic problem. Learning from different countries and about various aspects of COVID-19 is even more important and relevant. Countries, professionals and researchers will be able to learn from each other and to contribute in the effort of combating the problem of COVID-19 by establishing better linkages with researchers and professionals from different countries and experts from different fields.\r\nThe Center for International Health of Ludwig Maximilians University has a wide network of institutions and individuals throughout the continents and with different expertise and skill sets. This network and strength of individuals and institutions can be enhanced for a global effort of combating the pandemic by exchanging knowledge, skills and ideas. We propose a simple approach of facilitating the network and knowledge sharing by utilizing the CIH\u0092s 2020 Call for Proposals on One Health Funds.\r\nThrough this project, \u0093OH-Knowledge Cafe\u0094, we will bring together the expertise and network of researchers and professionals from various disciplines, countries and expertise to enable cross learning, sharing and network building. The project will ensure that funding and contribution from the CIHLMU \/DAAD\/BMZ and network partners will be duly acknowledged in all events and products developed.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> COVID0476<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2020 - Noviembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27088\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Variabilidad geogr\u00e1fica del impacto por d\u00e9ficit o postergaci\u00f3n de atenciones hospitalarias para enfermedades cr\u00f3nicas frente a la pandemia COVID-19\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27088\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27088\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La pandemia por COVID-19 supone una reorganizaci\u00f3n del sistema de salud para hacer frente a la hospitalizaci\u00f3n de pacientes cr\u00edticos, que seg\u00fan la evidencia internacional oscila entre un 9% y el 21% de los casos reportados (Paterlini, 2020). En el marco de un sistema de salud con listas de espera quir\u00fargica que alcanza las 237.416 personas (Minsal, 2019) y con una capacidad de camas que queda copada por las enfermedades no COVID-19, esta investigaci\u00f3n se pregunta por la resiliencia y reconfiguraci\u00f3n del sistema de salud para convivir con las otras enfermedades en el contexto de pandemia.\r\nLa investigaci\u00f3n tiene dos focos: (1) La configuraci\u00f3n territorial, ya que tanto la oferta de salud (entendida como la infraestructura y los recursos) como la demanda en salud (entendida como la prevalencia de enfermedades y la composici\u00f3n demogr\u00e1fica de los territorios) se distribuyen de forma desigual en el pa\u00eds; (2) Suponiendo la postergaci\u00f3n de las atenciones hospitalarias, la investigaci\u00f3n tambi\u00e9n pone el foco en las pr\u00e1cticas que se han desarrollado al interior de las familias para enfrentar los problemas de salud en el contexto de la pandemia y c\u00f3mo estas pr\u00e1cticas pudieran haber estado condicionadas por la realidad socioecon\u00f3mica de los hogares y el territorio.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> BIP 40014269<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2020 - Junio 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26935\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Mapa de reservas de aguas subterr\u00e1neas en el Limar\u00ed\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26935\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26935\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo general: contribuir con informaci\u00f3n y metodolog\u00eda de estudio inexistente sobre la ubicaci\u00f3n y la estimaci\u00f3n de las reservas en agua subterr\u00e1nea para descubrir nuevos acu\u00edferos, monitorear y gestionar su rol h\u00eddrico, especialmente en periodo de sequ\u00eda, en la cuenca de Limar\u00ed, en la Regi\u00f3n de Coquimbo. Objetivos espec\u00edficos: (i) identificar \u00e1reas donde los acu\u00edferos se encuentran bajo fuertes presiones antropog\u00e9nicas o naturales y donde hay un alto grado de incertidumbre sobre los recursos subterr\u00e1neos; (ii) en cada punto identificado, evaluar el contenido en agua de los acu\u00edferos, sus bases y sus techos con la t\u00e9cnica de Magnetic Resonance Sounding (MRS); (iii) contribuir en la elaboraci\u00f3n de una metodolog\u00eda para determinar las reservas en agua subterr\u00e1nea; (iv) construir un modelo tridimensional de las reservas de agua subterr\u00e1nea presentes en la regi\u00f3n; (v) dise\u00f1ar un plan que permita monitorear y gestionar eficientemente los acu\u00edferos de la zona como recurso h\u00eddrico econ\u00f3mico-social de la cuenca del Limar\u00ed.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2020 - Enero 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26199\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Predictores socioecon\u00f3micos y psicobiol\u00f3gicos del desempe\u00f1o acad\u00e9mico en estudiantes de primer a\u00f1o de pedagog\u00eda\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26199\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26199\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]aaaa[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2020 - Enero 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26403\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Predictores socioecon\u00f3micos y psicobiol\u00f3gicos del desempe\u00f1o acad\u00e9mico en estudiantes de primer a\u00f1o de pedagog\u00eda\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26403\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26403\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]aaaa[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2020 - Marzo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26350\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia Ecoinnovaci\u00f3n Agroalimentaria Regional de O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26350\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26350\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Implementar un sistema de Ecoinnovaci\u00f3n agroalimentaria regional, que permita a partir de la gastronom\u00eda, relacionar actores y entorno de una nueva forma, para mejorar la competitividad y valor de la cadena a nivel regional.  \r\n&#61607;\tActores de la cadena agroalimentaria articulados a trav\u00e9s de una Comunidad de Pr\u00e1ctica, funcionando y gestionada por la UOH y un Centro de Interpretaci\u00f3n Gastron\u00f3mico implementado y gestionado por ASEGMI.\r\n&#61607;\tCadena agroalimentaria mejora su competitividad a partir de nuevos canales de comercializaci\u00f3n (alianzas comerciales, puntos de venta y plataforma comercial); nuevas formas de promoci\u00f3n (ferias campesinas y escolares y encuentros gastron\u00f3micos eco innativos, basados en el ecodise\u00f1o sistematizadas), nuevos productos y envasados y un Sello de \u0093verde\u0094 regional para restaurantes, basado en la calidad y uso de pr\u00e1cticas de eco innovaci\u00f3n para potenciar la imagen regi\u00f3n y el turismo gastron\u00f3mico.\r\n&#61607;\tCampa\u00f1a de activaci\u00f3n comunicacional promoviendo la eco innovaci\u00f3n en pleno funcionamiento, gestionada por ASEGMI.\r\n&#61607;\tLaboratorio de eco innovaci\u00f3n agroalimentaria creado al interior de la UOH con sus l\u00edneas de investigaci\u00f3n, capacitaci\u00f3n y extensi\u00f3n en pleno funcionamiento[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2020 - Julio 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26529\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estudio psicosocial de los ciclos de radicalizaci\u00f3n de las protestas en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26529\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26529\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Los principales objetivos de este proyecto son:  1- Entender los diferentes ciclos de radicalizaci\u00f3n a partir del an\u00e1lisis de la din\u00e1mica de protesta basada en la interacci\u00f3n entre participantes y autoridades. 2- Analizar los cambios en la din\u00e1mica de protesta de acuerdo con c\u00f3mo se percibe que las autoridades tratan de facilitar u obstaculizar que se lleven a cabo manifestaciones. 3- Identificar episodios cr\u00edticos, basados en las medidas implementadas por del gobierno y carabineros con respecto a la protesta, que puedan funcionar como base para que aquellos que no participan en las manifestaciones pueden legitimar las acciones m\u00e1s radicales de protesta.  4- Describir las caracter\u00edsticas asociadas a aquellas acciones radicales de protesta que pueden ser deslegitimadas y consideradas como una amenaza por parte de aquellos que no participan en las manifestaciones.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11201336<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2020 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26105\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Adquisici\u00f3n y uso de variables sociofon\u00e9ticas del espa\u00f1ol chileno en el habla de ni\u00f1os, ni\u00f1as y sus tutores\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26105\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26105\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto de investigaci\u00f3n examina dos de los rasgos m\u00e1s sobresalientes de la variaci\u00f3n sociofon\u00e9tica en el espa\u00f1ol chileno: la producci\u00f3n variable del grupo conson\u00e1ntico \/t&#638;\/ y la variaci\u00f3n alof\u00f3nica del fonema \/t&#8747;\/. Ambos fen\u00f3menos han sido, y contin\u00faan siendo, de sumo inter\u00e9s para quienes estudian nuestro dialecto. Un importante n\u00famero de trabajos revela, largamente, que el uso de dichas variables y sus respectivas variantes, est\u00e1 condicionado por una serie de factores ling\u00fc\u00edsticos y extraling\u00fc\u00edsticos (sociales). \r\nEsta abundante literatura, sin embargo, se centra principalmente en hablantes adultos y adultos-j\u00f3venes, dejando el estudio de la adquisici\u00f3n y desarrollo del uso de estas variables socioling\u00fc\u00edsticas en el habla de ni\u00f1os\/as chilenos como un terreno que invita fuertemente a su exploraci\u00f3n.\r\nLa investigaci\u00f3n tiene como objetivo general conocer el proceso de adquisici\u00f3n y desarrollo de\r\nlos patrones de uso de la variaci\u00f3n del grupo conson\u00e1ntico \/t&#638;\/ y el fonema \/t&#8747;\/, en el habla de ni\u00f1os y ni\u00f1as\r\nchilenos y sus cuidadores.\r\nLos datos de este estudio ser\u00e1n obtenidos a partir de actividades de interacci\u00f3n\r\nnatural\/espont\u00e1nea di\u00e1dica entre ni\u00f1o\/a y tutor\/a.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2020 - Abril 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26145\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Que&#769; Comi&#769;an, Do&#769;nde Vivi&#769;an: Un Ana&#769;lisis Cri&#769;tico de los Proxies no Morfolo&#769;gicos Utilizados en Paleoecologi&#769;a de Mami&#769;feros Fo&#769;siles, Mediante el Estudio de las Variables Ambientales, Clima&#769;ticas y\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26145\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26145\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Fondecyt postdoctorado N\u00b0 3200806 An\u00e1lisis de la dieta de los mam\u00edferos extintos que vivieron en Chile Central durante el Pleistoceno[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2020 - Abril 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26495\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Mechanism Design in Complex Market\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26495\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26495\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Market design plays a key role in contexts where asymmetric information is relevant and there are di&#65533;culties arising from the complexities of each particular market. Moreover, in real world situations, it is important to bridge the gap between the theoretical insights developed through mechanism design and the implementability issues stressed in the market design literature.\r\nReal world situations might be complex for di&#8629;erent reasons, and in this proposal I plan to study two issues which up to now have not been fully analyzed in this theoretical\/applied interface. The first is regulation in the presence of vertical structures, an issue which is very common in industrial organization, but it has received surprisingly little attention in the mechanism design literature. The second is the design of new markets for natural resources, where property rights are crucial to their e&#65533;cient use, but dynamic issues make standard simple solutions very di&#65533;cult to implement and they usually perform poorly.\r\nCurbing the monopoly power of firms is a fundamental issue for regulators where the cost structure makes a monopoly unavoidable in the first place. In particular, the study of simple mechanisms that help with this goal becomes relevant. Firms are better informed about its production cost or the demand that they faced. This information gives them infor- mational rents that the regulators attempt to control to increase social welfare. While this is a well-studied problem by economists, it still generates challenges due to the complexity of real world situations. The granting of a monopoly right and the establishment of certain rules (like a quantity to produce or a maximum price to be set) is not the end of the story. Subsequently, the regulated firm will deal with downstream firms, which in turn might have significant market power in its dealings with consumers and even providers. In the first project, I study how an agent designs a mechanism to allocate resources that afterwards turns the chosen firm downstream into a mechanism designer on its on. Applications include infrastructure regulation: for example airports that in turn chose how to deal with airlines, which use their market power to extract rent from consumers.\r\nCreating markets under the \u0093tragedy of the commons\u0094 has a long tradition in economics, dating back to Pigou (1920) . The basic intuition is simple: prices would provide agents with the right scarcity signals, leading to an e&#65533;cient resource allocation. However, dynamic issues and the uncertainty about the real value of di&#8629;erent uses for the resource introduce significant challenges. On the second project, I study e&#65533;cient mechanisms in a dynamic framework where the value of the asset is known only by experimentation of investors. A general objective of this project is to study the conditions for which simple mechanism can be e&#65533;cient on one hand, and furthermore they increase the social welfare.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2020 - Abril 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26481\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Effects of climate change on xylem traits of woody species across environmental gradients in the Mediterranean Andes of central Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26481\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26481\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Forest dynamics have been affected by the high rates of greenhouse gas emissions that have direct consequences on global warming. This phenomenon is evident with the intensification of mega drought events in various parts of the world, including Chilean forests. It is still unclear how climate change may affect tree and shrub growth, especially in altitude regions such as the Mediterranean Andes of Central Chile (MACC) and how these populations would react to drought events on a timescale. In this sense, tree rings is one of the most important proxies for reconstructing environmental data, as trees contain historical records of previous growth conditions at annual resolution, which seems a useful tool to know the variations in xylem traits of woody species over time. One of the most important advances in tree-ring studies has been the additional focus on anatomical (i.e. vessels and wood density) and ecophysiological (i.e. carbon stable isotopes) features, since shows tree sensitivity to intra-seasonal environmental factors. The present proposal seek to investigate the adaptive strategies of woody species, based on xylem functional traits, for survival in current climate change scenarios on latitudinal and altitudinal gradients of the MACC, complementing dendrochronological, anatomical and isotopic analysis. This allow us to order to define priority locations for conservation and restoration projects and to identify which regions and populations are most vulnerable or resistant to severe climate change. We will test four hypotheses: (i) woody species populations from xeric sites have developed throughout their evolutionary history a hydraulic structure oriented to safety in comparison with the populations of wet sites; (ii) populations of all sites will have an increase of water use efficiency (iWUE) over time, as a result of a climate change adaptability strategy of trees, but it will not necessarily be reflected in higher trunk biomass; and (iii) xylem traits varied by altitudinal gradient affecting tree growth, being the populations of tree lines those that have trait values more resistant to current climatic change, and hence, more adapted to future scenarios of climate change. To test those hypotheses, we will select and will sample trees and shrub population of MACC (30-35\u00b0S, 71-71.5\u00b0W). We will use bibliography, expert interviews and local communities to select potential sites, as well as a drone (Phantom 4RTK\u00ae) to analyze vegetation characteristics. Preliminarily, the genera Prosopis, Acacia, Berberis and Adesmia will be selected because present wide distribution in MACC and high dendrochronological potential. Thus, this project will show us how they will respond in the future under the current climatic trends, identifying which regions and populations are the most vulnerable to climate change in the Andes of central Chile. Likewise, these results will serve to measure how the impacts of environmental variations have been in a region with high levels of endemism in South America, both in structure, hydraulic plasticity and carbon storage, being useful to be in conservation and restoration project, as well as replicated in future studies of other areas, both in South America and the world.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Patrocinante<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2020 - Marzo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25975\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia de  un Modelo de Inocuidad agroalimentaria regional\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25975\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25975\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto tiene como objetivo, ejecutar un sistema de extensi\u00f3n para productores hort\u00edcolas y ap\u00edcolas de la regi\u00f3n de O\u0092Higgins, junto con un sistema de monitoreo de peligros alimentarios, un sistema de cultura de inocuidad y un SELLO o marca de certificaci\u00f3n en base a criterios de inocuidad alimentaria.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2020 - Febrero 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26003\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Image Modeling and Processing for REmote SenSing in agriculture (IMPRESS)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26003\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26003\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The field of remote sensing is experiencing an unprecedented acceleration. Besides the large public programs such as Sentinel (see e.g. https:\/\/sentinel.esa.int\/web\/sentinel\/missions\/sentinel-2), private actors are creating fleets of micro-satellites capable of  monitoring of the earth with daily revisits. This abundant and cheap data is creating opportunities for developing novel applications for the monitoring of industrial and agricultural activity. The automatic exploitation of this data is bound to specific application domain knowledge, which  requires a mastery of advanced techniques such as computer vision and machine learning, as well as expert knowledge in the field of agriculture. To do this, the team must master earth observation satellites, be able to define the adequate mathematical detection theories, and build on a deep knowledge of satellite image processing, while also including expert knowledge in agriculture. This project aims at uniting competences across the fields of computer vision and machine learning, remote sensing to address emerging applications in agronomy. This project will in addition foster the creation of reproducible research by adopting a reproducible research methodology thus contributing the resulting algorithms to the journal Image Processing On-Line (IPOL). The IPOL journal is an initiative to establish a clear and reproducible state-of-the-art in the domain of image processing and computer vision.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2020 - Febrero 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26089\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Image Modeling and Processing for REmote SenSing in agriculture (IMPRESS)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26089\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26089\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The field of remote sensing is experiencing an unprecedented acceleration. Besides the large public programs such as Sentinel (see e.g. https:\/\/sentinel.esa.int\/web\/sentinel\/missions\/sentinel-2), private actors are creating fleets of micro-satellites capable of  monitoring of the earth with daily revisits. This abundant and cheap data is creating opportunities for developing novel applications for the monitoring of industrial and agricultural activity. The automatic exploitation of this data is bound to specific application domain knowledge, which  requires a mastery of advanced techniques such as computer vision and machine learning, as well as expert knowledge in the field of agriculture. To do this, the team must master earth observation satellites, be able to define the adequate mathematical detection theories, and build on a deep knowledge of satellite image processing, while also including expert knowledge in agriculture. This project aims at uniting competences across the fields of computer vision and machine learning, remote sensing to address emerging applications in agronomy. This project will in addition foster the creation of reproducible research by adopting a reproducible research methodology thus contributing the resulting algorithms to the journal Image Processing On-Line (IPOL). The IPOL journal is an initiative to establish a clear and reproducible state-of-the-art in the domain of image processing and computer vision.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2020 - Marzo 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26116\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fondecyt Regular 1201283 &#8211; Reprogramming cardiovascular health after intrauterine hypoxia: epigenetics, antioxidants and endogenous gasotransmitters\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26116\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26116\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]There are more than 41 million deaths per year worldwide, 71% of them are due to non-communicable diseases (NCDs), with cardiovascular (CV) causes taking the first place. Adverse intrauterine conditions increase the risk of developing NCDs during the life course, a phenomenon known as Developmental Origins of Health and Disease (DOHaD).\r\nThe most frequent and clinically relevant adverse condition during fetal life is intrauterine hypoxia (IH), which is associated with a high perinatal morbi-mortality. The molecular mechanisms that could be involve in IH causes and consequences are an important aspect in most of the pregnancies at high altitudes (> 2500m), and in 3-4% of the pregnancies with utero-placental complications at lowlands. \r\nNitric oxide (NO), carbon monoxide (CO) and hydrogen sulfide (H2S) are endogenous gasotransmitters with vasodilator properties that can regulate cardiovascular functions. These gasotransmitters may be affected by intrauterine chronic hypoxia- induced oxidative stress, eliciting vascular programming and deriving in cardiovascular dysfunction along life course. \r\nAlthough these gasotransmitters have shown to determine endothelial, smooth muscle and cardiac function, the role of them in the fetal programming CV dysfunction due to developmental hypoxia and their relationship with oxidative stress is still unknown. \r\n\r\nOur hypothesis is that the intrauterine development in chronic hypoxia programms the gasotransmitters pathways (NO, CO and H2S) in the heart and blood vessels through oxidative stress, which impacts in the short, medium and long term cardiovascular function. Therefore, an oral treatment with antenatal melatonin will prevent the hypoxic-induced cardiovascular impairment.\r\n\r\nIn this proposal, we aim to study, in a well-characterized guinea pig model, the origins and outcomes of cardiovascular dysfunction resulting from IH, by characterizing the functional, structural and molecular aspects of vasoactive mechanisms dependent on endogenous gasotransmitters, in the heart and blood vessels. Moreover, as fetal growth restriction and cardiovascular programming are related with hypoxia induced-oxidative stress, we will implement an antenatal treatment with melatonin, a proved antioxidant, to test the prevention of IH-induced cardiovascular risks in the short-, mediate- and long-term. \r\n\r\nTo address these aims, we will study the effects of intrauterine chronic hypoxia and oxidative stress on the NO, CO and H2S related pathways of the cardiovascular system in guinea pigs. We will describe the NO, CO and H2S related pathways, its epigenetic changes and their roles as important regulators of function, structure and biomechanical properties of heart and vessels, under hypoxia induced-oxidative stress.\r\n\r\nThe aforementioned will be done in animals gestated under IH, with or without antenatal melatonin treatment, and follow the cardiovascular function from fetus to adulthood. The methodology is an in vivo non-invasive evaluation of the function and structure of the cardiovascular system (ultrasound); an ex vivo function and biomechanical characterization of heart and arteries (Langendorff, wire myography, biomechanical tests); and in vitro determinations of genetic, protein and epigenetic expression in heart and several vascular beds; at different stages of life.\r\nThese approaches will permit us to correlate and integrate the short-, mediate- and long-term cardiovascular effects related to the gasotransmitters pathways, in the offspring gestated under chronic hypoxia. In addition, we will evaluate a supported treatment with melatonin, to prevent intrauterine growth restriction and cardiovascular impairment after IH exposure, to test the relationship of gasotransmitters pathways with intrauterine oxidative stress.\r\n\r\nWe expect to unravel the mechanisms underlying IH- induced cardiovascular reprogramming focusing on oxidative stress and gasotransmitters, in order to potentiate melatonin treatment as a possible therapy in hypoxia related complicated pregnancies, either at high altitude or lowlands. This grant will effectively provide a valuable resource for the scientific and clinical community to pursue the understanding of cardiovascular NCDs programmed by intrauterine hypoxia, a worldwide burden still without effective therapeutic approach. Furthermore, this will add knowledge to the foundations for the development of novel therapies for intrauterine hypoxia, and the prevention of CV risk in fetuses, neonates and adults.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2020 - Abril 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26249\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Marcadores Metab\u00f3licos de Pron\u00f3stico de Severidad para Pacientes Covid-19.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26249\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26249\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2020 - Febrero 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26272\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Image Modeling and Processing for REmote SenSing in agriculture (IMPRESS)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26272\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26272\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The field of remote sensing is experiencing an unprecedented acceleration. Besides the large public programs such as Sentinel (see e.g. https:\/\/sentinel.esa.int\/web\/sentinel\/missions\/sentinel-2), private actors are creating fleets of micro-satellites capable of  monitoring of the earth with daily revisits. This abundant and cheap data is creating opportunities for developing novel applications for the monitoring of industrial and agricultural activity. The automatic exploitation of this data is bound to specific application domain knowledge, which  requires a mastery of advanced techniques such as computer vision and machine learning, as well as expert knowledge in the field of agriculture. To do this, the team must master earth observation satellites, be able to define the adequate mathematical detection theories, and build on a deep knowledge of satellite image processing, while also including expert knowledge in agriculture. This project aims at uniting competences across the fields of computer vision and machine learning, remote sensing to address emerging applications in agronomy. This project will in addition foster the creation of reproducible research by adopting a reproducible research methodology thus contributing the resulting algorithms to the journal Image Processing On-Line (IPOL). The IPOL journal is an initiative to establish a clear and reproducible state-of-the-art in the domain of image processing and computer vision.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2020 - Septiembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26273\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia F\u00e1brica Digital de la Sexta\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26273\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26273\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Los laboratorios de fabricaci\u00f3n digital son espacios que cuentan con maquinaria y personal capacitado para facilitar el dise\u00f1o y desarrollo de prototipos y para promover la innovaci\u00f3n en productos, procesos y servicios. Se conciben como laboratorios que facilitan herramientas de fabricaci\u00f3n avanzada y capacidades a la comunidad en general, pudiendo ser m\u00e1s enfocados a emprendedores, empresas e institutos de investigaci\u00f3n. Una caracter\u00edstica com\u00fan es que sirven como plataforma para estimular el aprendizaje y la invenci\u00f3n en la comunidad. Las m\u00e1quinas y capacidades t\u00e9cnicas instaladas en estos laboratorios brindan la oportunidad de encontrar soluciones innovadoras a problemas comunes y ser incubadores de microemprendimientos que resuelvan problemas de forma innovadora y sustentable.\r\n\r\nEl primer laboratorio de fabricaci\u00f3n digital, junto con el concepto FabLab, aparece en el MIT (Massachussets Institute of Technology, Estados Unidos) en el a\u00f1o 2000. Actualmente, existe una red mundial de alrededor de 3000 FabLabs distribuidos en 5 continentes. En Chile se pueden encontrar 17 de estos laboratorios, la mayor\u00eda de ellos concentrados en la Regi\u00f3n Metropolitana; 2 en la Regi\u00f3n del Maule y ninguno en la Regi\u00f3n de O\u0092Higgins. La ausencia de un laboratorio regional est\u00e1 en concordancia con estad\u00edsticas del a\u00f1o 2016 que reportan apenas 118 m2 de espacios dedicados a innovaci\u00f3n en la Regi\u00f3n de O\u0092Higgins frente a 27 936 m2 en la Regi\u00f3n Metropolitana. En ese contexto, la Regi\u00f3n de O\u0092Higgins es la segunda regi\u00f3n con menor superficie dedicada a innovaci\u00f3n.\r\n\r\nLa instalaci\u00f3n de un laboratorio de fabricaci\u00f3n digital en la Regi\u00f3n de O\u0092Higgins se identifica como una gran oportunidad para promover la innovaci\u00f3n, brindando acceso a equipos y a capacitaciones sobre herramientas de fabricaci\u00f3n avanzada a industrias y emprendedores regionales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2020 - Marzo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26282\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia de  un Modelo de Inocuidad agroalimentaria regional\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26282\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26282\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto tiene como objetivo, ejecutar un sistema de extensi\u00f3n para productores hort\u00edcolas y ap\u00edcolas de la regi\u00f3n de O\u0092Higgins, junto con un sistema de monitoreo de peligros alimentarios, un sistema de cultura de inocuidad y un SELLO o marca de certificaci\u00f3n en base a criterios de inocuidad alimentaria.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2020 - Marzo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26301\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia de  un Modelo de Inocuidad agroalimentaria regional\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26301\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26301\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto tiene como objetivo, ejecutar un sistema de extensi\u00f3n para productores hort\u00edcolas y ap\u00edcolas de la regi\u00f3n de O\u0092Higgins, junto con un sistema de monitoreo de peligros alimentarios, un sistema de cultura de inocuidad y un SELLO o marca de certificaci\u00f3n en base a criterios de inocuidad alimentaria.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2020 - Septiembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26337\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia F\u00e1brica Digital de la Sexta\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26337\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26337\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Los laboratorios de fabricaci\u00f3n digital son espacios que cuentan con maquinaria y personal capacitado para facilitar el dise\u00f1o y desarrollo de prototipos y para promover la innovaci\u00f3n en productos, procesos y servicios. Se conciben como laboratorios que facilitan herramientas de fabricaci\u00f3n avanzada y capacidades a la comunidad en general, pudiendo ser m\u00e1s enfocados a emprendedores, empresas e institutos de investigaci\u00f3n. Una caracter\u00edstica com\u00fan es que sirven como plataforma para estimular el aprendizaje y la invenci\u00f3n en la comunidad. Las m\u00e1quinas y capacidades t\u00e9cnicas instaladas en estos laboratorios brindan la oportunidad de encontrar soluciones innovadoras a problemas comunes y ser incubadores de microemprendimientos que resuelvan problemas de forma innovadora y sustentable.\r\n\r\nEl primer laboratorio de fabricaci\u00f3n digital, junto con el concepto FabLab, aparece en el MIT (Massachussets Institute of Technology, Estados Unidos) en el a\u00f1o 2000. Actualmente, existe una red mundial de alrededor de 3000 FabLabs distribuidos en 5 continentes. En Chile se pueden encontrar 17 de estos laboratorios, la mayor\u00eda de ellos concentrados en la Regi\u00f3n Metropolitana; 2 en la Regi\u00f3n del Maule y ninguno en la Regi\u00f3n de O\u0092Higgins. La ausencia de un laboratorio regional est\u00e1 en concordancia con estad\u00edsticas del a\u00f1o 2016 que reportan apenas 118 m2 de espacios dedicados a innovaci\u00f3n en la Regi\u00f3n de O\u0092Higgins frente a 27 936 m2 en la Regi\u00f3n Metropolitana. En ese contexto, la Regi\u00f3n de O\u0092Higgins es la segunda regi\u00f3n con menor superficie dedicada a innovaci\u00f3n.\r\n\r\nLa instalaci\u00f3n de un laboratorio de fabricaci\u00f3n digital en la Regi\u00f3n de O\u0092Higgins se identifica como una gran oportunidad para promover la innovaci\u00f3n, brindando acceso a equipos y a capacitaciones sobre herramientas de fabricaci\u00f3n avanzada a industrias y emprendedores regionales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2020 - Febrero 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26344\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia D&#8217;Agen para exportaci\u00f3n en fresco\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26344\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26344\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La superficie plantada de ciruelo europeo (Prunus domestica L.) se ha incrementado considerablemente en los \u00faltimos a\u00f1os en Chile, siendo hoy cercana a las 13.000 hect\u00e1reas. Seg\u00fan cifras de ODEPA (2019), 8.730 hect\u00e1reas se encuentran plantadas en la regi\u00f3n de O\u0092Higgins, lo que representa un 67,5% de la superficie plantada a nivel nacional; mientras que, a nivel regional, es el tercer cultivo con mayor superficie despu\u00e9s del cerezo y vid de mesa. La representaci\u00f3n de este cultivo en Chile, se basa \u00fanicamente en la variedad \u0091D\u0092Agen\u0092, que concentra el 95% de la superficie plantada, lo que se debe principalmente a las buenas caracter\u00edsticas productivas y organol\u00e9pticas que presenta, adem\u00e1s, de la favorable adaptabilidad que tiene a nuestras condiciones edafoclim\u00e1ticas, en especial en la regi\u00f3n de O'Higgins. Respecto al destino de esta fruta, del total de la producci\u00f3n en la regi\u00f3n de O'Higgins, un 91,2% de ella se destina a la industria y tan s\u00f3lo un 7,8% a exportaci\u00f3n de fruta en fresco.\r\n\r\nEn los \u00faltimos a\u00f1os tambi\u00e9n se ha abierto el mercado asi\u00e1tico para la exportaci\u00f3n de ciruela europea en estado fresco. Este tipo de producto alcanza precios mucho mayores que el deshidratado, asegurando retornos por hect\u00e1rea de hasta un 25% mayor a los ingresos que se alcanzan con la fruta destinada a la agroindustria. Las exportaciones de ciruela europea fresca se duplicaron en la temporada 2017-2018 con 6.224 ton, en relaci\u00f3n a la temporada anterior. Como consecuencia, muchas empresas han decidido comenzar a destinar parte de sus huertos para fresco (30%), resultando la variedad D'Agen como la segunda fruta, despu\u00e9s de las cerezas, m\u00e1s demandada por el mercado chino. Este cambio de objetivo en la producci\u00f3n de ciruelo D\u0092Agen ha generado la necesidad de modificar el manejo com\u00fanmente dado a sus huertos pues \u00e9stos se caracterizan por tener \u00e1rboles de gran altura y cosecha mecanizada. Hay un desconocimiento de c\u00f3mo se desarrolla el fruto y c\u00f3mo madura, lo que impide definir los par\u00e1metros de calidad \u00f3ptimos para obtener fruta fresca Premium. El est\u00e1ndar de calidad que exige el mercado fresco, no s\u00f3lo se basa en alto dulzor, sino que tambi\u00e9n en calibres grandes, uniformidad en el color de la piel, entre otros factores.\r\nSi bien la industria de la ciruela europea para exportaci\u00f3n en fresco no es nueva, existe un desconocimiento general, a nivel intrapredial (productores) y de exportadoras en cuanto a las directrices de producci\u00f3n y de postcosecha para la exportaci\u00f3n de fruta en fresco. Dentro de los problemas identificados se encuentran los siguientes: \r\n1.\tFalta de mano de obra especializada \r\n2.\tConcentraci\u00f3n de la producci\u00f3n en una \u00fanica variedad. \r\n3.\tHuertos tradicionales para la producci\u00f3n de ciruela deshidratas. \r\n4.\tDesconocimiento de \u00cdndices de madurez a cosecha. \r\n5.\tDesconocimiento de los manejos en cosecha y postcosecha para exportaci\u00f3n en fresco a mercados distantes.\r\n6.\tFalta de un an\u00e1lisis econ\u00f3mico de la producci\u00f3n mixta. \r\n\r\nEn cuanto a la oportunidad, esta propuesta buscar abordar las problem\u00e1ticas planteadas a trav\u00e9s de la difusi\u00f3n y transferencia de directrices tecnol\u00f3gicas que son identificadas en diversos puntos de la cadena de producci\u00f3n-exportaci\u00f3n y comercializaci\u00f3n:\r\n\u0095\tCapacitaci\u00f3n de la mano de obra existente en la regi\u00f3n en labores agr\u00edcolas espec\u00edficas para la producci\u00f3n en fresco de ciruela D\u0092Agen.\r\n\u0095\tB\u00fasqueda de nuevas alternativas en variedades o clones existentes de ciruela europea para deshidratado, que permitan descomprimir las labores agron\u00f3micas y as\u00ed ampliar la oferta de esta fruta fresca. \r\n\u0095\tDefinici\u00f3n de par\u00e1metros de madurez a cosecha y desarrollar directrices tecnol\u00f3gicas para la obtenci\u00f3n de \u00e9stos mismos, mediante el manejo de pr\u00e1cticas agron\u00f3micas, como poda y raleo.\r\n\u0095\tDefinici\u00f3n de los manejos en postcosecha, desde huerto a packing, y posterior almacenaje y transporte, en conjunto con las exportadoras\r\n\u0095\tAn\u00e1lisis de factibilidad t\u00e9cnica-econ\u00f3mico-social de distintos escenarios productivos en la reconversi\u00f3n paulatina e inteligente del destino de producci\u00f3n desde el deshidratado hacia la producci\u00f3n de fruta fresca.\r\n\r\nEl objetivo general de la propuesta es:\r\nIncrementar la competitividad de la industria de la ciruela D\u0092agen en la regi\u00f3n de O\u0092Higgins, mediante el desarrollo de directrices tecnol\u00f3gicas de producci\u00f3n en pre y postcoseha para la obtenci\u00f3n de fruta de calidad y condici\u00f3n \u00f3ptima de exportaci\u00f3n a mercados distantes.\r\n\r\nLos objetivos espec\u00edficos son:\r\n1.\tConformaci\u00f3n \u0093Mesa T\u00e9cnica Regional de la Ciruela Fresca\r\n2.\tEvaluar el efecto de diferentes pr\u00e1cticas de manejo realizadas bajo distintas condiciones de huerto de ciruela D\u0092Agen descritas, seg\u00fan objetivo del destino (fresco, deshidratado, mixto), durante el per\u00edodo de crecimiento del fruto, para la regulaci\u00f3n de la carga frutal y su efecto sobre el rendimiento del cultivo y la calidad de fruta.\r\n3.\tDesarrollar manejos y protocolos de postcosecha, para un comportamiento \u00f3ptimo durante almacenaje y transporte, que aseguren la llegada de ciruelas D\u0092Agen a mercados distantes, con una condici\u00f3n organol\u00e9ptica y sanitaria de categor\u00eda superior.\r\n4.\tDeterminar indicadores socio-econ\u00f3micos para la toma de decisi\u00f3n de la reconversion de los huertos de ciruela D\u0092Agen, desde el deshidratado a fresco.\r\n\r\nLa presente iniciativa se enmarca al destino \u0093transferencia tecnol\u00f3gica\u0094, correspondiente a la transferencia de conocimiento sistem\u00e1tico, con el prop\u00f3sito de generar y agregar valor a nuestra industria frut\u00edcola. Los principales resultados de este proyecto son: \r\n\r\n1.\tManual de Directrices Tecnol\u00f3gicas para la producci\u00f3n en fresco de ciruelas europeas var. D\u0092Agen. \r\n2.\tConstituci\u00f3n de una mesa regional de trabajo de la ciruela D\u0092Agen en fresco. \r\n3.\tCatastro de productores y transferencistas entrenados. \r\n4.\tCartillas divulgativas de material de cosecha (indicadores de \u00edndice de madurez y cosecha)[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2020 - Marzo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26423\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia de  un Modelo de Inocuidad agroalimentaria regional\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26423\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26423\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto tiene como objetivo, ejecutar un sistema de extensi\u00f3n para productores hort\u00edcolas y ap\u00edcolas de la regi\u00f3n de O\u0092Higgins, junto con un sistema de monitoreo de peligros alimentarios, un sistema de cultura de inocuidad y un SELLO o marca de certificaci\u00f3n en base a criterios de inocuidad alimentaria.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2020 - Abril 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26450\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Smart nitrogen fertilizer to face climate change and food security\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26450\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26450\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2020 - Abril 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26451\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Unraveling the influence of anthropogenic intervention on bacterial communities and nutrient cycling related to GHG emission from wetland\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26451\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26451\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2020 - Marzo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26520\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Generalized Differentiation And Variational Analysis Of Probability Functions\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26520\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26520\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Investigaci\u00f3n b\u00e1sica en problemas de optimizaci\u00f3n estoc\u00e1stica.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26528\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estudio Longitudinal de Salud Mental en Estudiantes Universitarios #enlaUvamosjuntxs\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26528\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26528\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Estudio multic\u00e9ntrico dirigido por World Mental Health International College Student (WMH-ICS)[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2020 - Diciembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26663\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            ESTUDIO TIARA: impacto psico-social del Coronavirus (COVID-19) en Argentina, Chile y Bolivia.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26663\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26663\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto regional de estudio psicosocial se conforma ante la crisis global por enfermedad de Coronavirus 2019 (COVID-19), la cual fue declarada pandemia global, el 11 de marzo pasado, por la OMS1. El objetivo del Proyecto es evaluar el impacto social y en salud mental que tiene la enfermedad en Argentina, Chile y Bolivia; como as\u00ed tambi\u00e9n generar evidencia para la toma de decisiones en pol\u00edticas de salud y sociales de cada pa\u00eds.\r\nEl estudio TIARA, estudio base del presente proyecto multic\u00e9ntrico, desarrollado e implementado por Silvina Arrossi y Silvina Ramos del CEDES (unidad asociada a CONICET), Argentina y otros investigadores del mismo pa\u00eds, se ampl\u00eda para generar un proyecto multic\u00e9ntrico que re\u00fane el esfuerzo de colaboraci\u00f3n de instituciones e investigadores de tres pa\u00edses, Argentina, Bolivia y Chile.\r\nEn Chile y Bolivia, est\u00e1 dirigido por equipos locales que re\u00fanen una vasta experiencia en estudios sociales, psiquiatr\u00eda, salud mental global y salud p\u00fablica. El estudio cuenta con el apoyo de co-investigadores y cuenta con el apoyo t\u00e9cnico del Departamento de Salud Mental del Ministerio de Salud de Chile, lo que beneficia el efecto traslacional del conocimiento que se genere.\r\n\r\nObjetivos de Investigaci\u00f3n\r\nEste estudio se propone analizar el impacto psico-social y en la vida cotidiana ante las medidas implementadas frente al COVID-19 en Chile y Bolivia, as\u00ed como tambi\u00e9n analizar las estrategias que est\u00e1 implementando la poblaci\u00f3n para sobrellevar estas medidas, tomando como base las recomendaciones de organismos de salud mental nacionales e internacionales. Por otra parte, se recabar\u00e1 informaci\u00f3n acerca de la posible percepci\u00f3n de los aspectos positivos de las medidas de confinamiento, de manera que se pueda hacer un seguimiento en el tiempo de la aceptabilidad e impacto que tienen en las personas y los hogares.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2020 - Febrero 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26706\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Image Modeling and Processing for REmote SenSing in agriculture (IMPRESS)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26706\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26706\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The field of remote sensing is experiencing an unprecedented acceleration. Besides the large public programs such as Sentinel (see e.g. https:\/\/sentinel.esa.int\/web\/sentinel\/missions\/sentinel-2), private actors are creating fleets of micro-satellites capable of  monitoring of the earth with daily revisits. This abundant and cheap data is creating opportunities for developing novel applications for the monitoring of industrial and agricultural activity. The automatic exploitation of this data is bound to specific application domain knowledge, which  requires a mastery of advanced techniques such as computer vision and machine learning, as well as expert knowledge in the field of agriculture. To do this, the team must master earth observation satellites, be able to define the adequate mathematical detection theories, and build on a deep knowledge of satellite image processing, while also including expert knowledge in agriculture. This project aims at uniting competences across the fields of computer vision and machine learning, remote sensing to address emerging applications in agronomy. This project will in addition foster the creation of reproducible research by adopting a reproducible research methodology thus contributing the resulting algorithms to the journal Image Processing On-Line (IPOL). The IPOL journal is an initiative to establish a clear and reproducible state-of-the-art in the domain of image processing and computer vision.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2020 - Diciembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26819\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            ESTUDIO TIARA: impacto psico-social del Coronavirus (COVID-19) en Argentina, Chile y Bolivia.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26819\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26819\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto regional de estudio psicosocial se conforma ante la crisis global por enfermedad de Coronavirus 2019 (COVID-19), la cual fue declarada pandemia global, el 11 de marzo pasado, por la OMS1. El objetivo del Proyecto es evaluar el impacto social y en salud mental que tiene la enfermedad en Argentina, Chile y Bolivia; como as\u00ed tambi\u00e9n generar evidencia para la toma de decisiones en pol\u00edticas de salud y sociales de cada pa\u00eds.\r\nEl estudio TIARA, estudio base del presente proyecto multic\u00e9ntrico, desarrollado e implementado por Silvina Arrossi y Silvina Ramos del CEDES (unidad asociada a CONICET), Argentina y otros investigadores del mismo pa\u00eds, se ampl\u00eda para generar un proyecto multic\u00e9ntrico que re\u00fane el esfuerzo de colaboraci\u00f3n de instituciones e investigadores de tres pa\u00edses, Argentina, Bolivia y Chile.\r\nEn Chile y Bolivia, est\u00e1 dirigido por equipos locales que re\u00fanen una vasta experiencia en estudios sociales, psiquiatr\u00eda, salud mental global y salud p\u00fablica. El estudio cuenta con el apoyo de co-investigadores y cuenta con el apoyo t\u00e9cnico del Departamento de Salud Mental del Ministerio de Salud de Chile, lo que beneficia el efecto traslacional del conocimiento que se genere.\r\n\r\nObjetivos de Investigaci\u00f3n\r\nEste estudio se propone analizar el impacto psico-social y en la vida cotidiana ante las medidas implementadas frente al COVID-19 en Chile y Bolivia, as\u00ed como tambi\u00e9n analizar las estrategias que est\u00e1 implementando la poblaci\u00f3n para sobrellevar estas medidas, tomando como base las recomendaciones de organismos de salud mental nacionales e internacionales. Por otra parte, se recabar\u00e1 informaci\u00f3n acerca de la posible percepci\u00f3n de los aspectos positivos de las medidas de confinamiento, de manera que se pueda hacer un seguimiento en el tiempo de la aceptabilidad e impacto que tienen en las personas y los hogares.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2020 - Febrero 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26875\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Image Modeling and Processing for REmote SenSing in agriculture (IMPRESS)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26875\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26875\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The field of remote sensing is experiencing an unprecedented acceleration. Besides the large public programs such as Sentinel (see e.g. https:\/\/sentinel.esa.int\/web\/sentinel\/missions\/sentinel-2), private actors are creating fleets of micro-satellites capable of  monitoring of the earth with daily revisits. This abundant and cheap data is creating opportunities for developing novel applications for the monitoring of industrial and agricultural activity. The automatic exploitation of this data is bound to specific application domain knowledge, which  requires a mastery of advanced techniques such as computer vision and machine learning, as well as expert knowledge in the field of agriculture. To do this, the team must master earth observation satellites, be able to define the adequate mathematical detection theories, and build on a deep knowledge of satellite image processing, while also including expert knowledge in agriculture. This project aims at uniting competences across the fields of computer vision and machine learning, remote sensing to address emerging applications in agronomy. This project will in addition foster the creation of reproducible research by adopting a reproducible research methodology thus contributing the resulting algorithms to the journal Image Processing On-Line (IPOL). The IPOL journal is an initiative to establish a clear and reproducible state-of-the-art in the domain of image processing and computer vision.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2020 - Septiembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26876\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia F\u00e1brica Digital de la Sexta\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26876\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26876\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Los laboratorios de fabricaci\u00f3n digital son espacios que cuentan con maquinaria y personal capacitado para facilitar el dise\u00f1o y desarrollo de prototipos y para promover la innovaci\u00f3n en productos, procesos y servicios. Se conciben como laboratorios que facilitan herramientas de fabricaci\u00f3n avanzada y capacidades a la comunidad en general, pudiendo ser m\u00e1s enfocados a emprendedores, empresas e institutos de investigaci\u00f3n. Una caracter\u00edstica com\u00fan es que sirven como plataforma para estimular el aprendizaje y la invenci\u00f3n en la comunidad. Las m\u00e1quinas y capacidades t\u00e9cnicas instaladas en estos laboratorios brindan la oportunidad de encontrar soluciones innovadoras a problemas comunes y ser incubadores de microemprendimientos que resuelvan problemas de forma innovadora y sustentable.\r\n\r\nEl primer laboratorio de fabricaci\u00f3n digital, junto con el concepto FabLab, aparece en el MIT (Massachussets Institute of Technology, Estados Unidos) en el a\u00f1o 2000. Actualmente, existe una red mundial de alrededor de 3000 FabLabs distribuidos en 5 continentes. En Chile se pueden encontrar 17 de estos laboratorios, la mayor\u00eda de ellos concentrados en la Regi\u00f3n Metropolitana; 2 en la Regi\u00f3n del Maule y ninguno en la Regi\u00f3n de O\u0092Higgins. La ausencia de un laboratorio regional est\u00e1 en concordancia con estad\u00edsticas del a\u00f1o 2016 que reportan apenas 118 m2 de espacios dedicados a innovaci\u00f3n en la Regi\u00f3n de O\u0092Higgins frente a 27 936 m2 en la Regi\u00f3n Metropolitana. En ese contexto, la Regi\u00f3n de O\u0092Higgins es la segunda regi\u00f3n con menor superficie dedicada a innovaci\u00f3n.\r\n\r\nLa instalaci\u00f3n de un laboratorio de fabricaci\u00f3n digital en la Regi\u00f3n de O\u0092Higgins se identifica como una gran oportunidad para promover la innovaci\u00f3n, brindando acceso a equipos y a capacitaciones sobre herramientas de fabricaci\u00f3n avanzada a industrias y emprendedores regionales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1201786<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2020 - Marzo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26508\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fondecyt 1201786 Reconstructing mobility, settlement, technology, and ecosystem services-use in the Atacama Desert by the end of the Pleistocene\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26508\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26508\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto que buscaba indagar en la realcion entre los primeros pobladores del desierto de atacama y su entorno a finales del Pleistoceno (12.000 a\u00f1os atr\u00e1s).[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26040\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Revista digital y escritura situada\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26040\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26040\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La propuesta consiste en la conformaci\u00f3n de un comit\u00e9 editorial de estudiantes de los cursos \u0093Narrativa chilena y latinoamericana\u0094 y \u0093Juventudes en sociedad\u0094, quienes, bajo la supervisi\u00f3n de los profesores de ambos cursos, elaborar\u00e1n una revista digital con publicaciones de rese\u00f1as de libros y columnas de opini\u00f3n. Los aportes para publicar en la revista ser\u00e1n realizados por sus compa\u00f1eras y compa\u00f1eros de ambos cursos y tendr\u00e1n que ver con el desarrollo tem\u00e1tico de los\r\nmismos.\r\nSe trata de una instancia innovadora por cuanto propicia una forma de aprendizaje a trav\u00e9s de escritura situada en un medio cultural que, luego de terminados los cursos respectivos, podr\u00e1 continuar en funcionamiento. El fondo para la implementaci\u00f3n de este proyecto solo se requerir\u00e1 por una \u00fanica vez y podr\u00e1 ser utilizado los a\u00f1os siguientes en la misma modalidad.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2020 - Enero 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26743\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            La construcci\u00f3n del \u0091otro\u0092 en tiempos de pandemia:  un an\u00e1lisis de las representaciones de la migraci\u00f3n en medios de noticias digitales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26743\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26743\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Materia Espec\u00edfica: Los objetivos de este proyecto son: 1) Analizar la representaci\u00f3n de la migraci\u00f3n a partir de la articulaci\u00f3n de distintas categor\u00edas de diferencia (ej.: g\u00e9nero, clase social, estatus migratorio, etnicidad u otras relativamente salientes); 2) Profundizar en la representaci\u00f3n del g\u00e9nero en noticias sobre migraci\u00f3n y pandemia. 3) Identificar los espacios de la migraci\u00f3n m\u00e1s com\u00fanmente representados y los significados construidos en torno a ellos; 4) Identificar los giros en la representaci\u00f3n de la migraci\u00f3n durante la pandemia; 5) Comparar las representaciones que hacen medios con distintas l\u00edneas editoriales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>COES<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26744\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Observatorio de Violencia y Legitimidad Social (OLES)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26744\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26744\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto naci\u00f3 de conversaciones con colegas de distintas universidades sobre el fen\u00f3meno de la violencia policial en las manifestaciones durante el Estallido Social que remeci\u00f3 a Chile el a\u00f1o 2019. Con un af\u00e1n de entender, al largo del tiempo, las din\u00e1micas de violencia y legitimidad social en el marco de manifestaciones en Chile, con un equipo de investigadoras de la Universidad Diego Portales (UDP, Monica Gerber y Macarena Orchard), postulamos a fondos de COES para implementar un estudio longitudinal que busca entender como la actual crisis de legitimidad de Carabineros lleva a la justificaci\u00f3n de actos violentos y, por ende, menores niveles de legitimidad social a trav\u00e9s del tiempo. Este proyecto obtuvo financiamiento de COES y de la UDP y, adem\u00e1s, de la European Association of Social Psychology (EASP), mostrando as\u00ed su relevancia te\u00f3rica y social, tanto a nivel nacional como internacional. A lo largo del proyecto, desarrollamos 4 grandes l\u00edneas de investigaci\u00f3n y organizamos un ciclo de Seminarios sobre el proyecto, el cual cont\u00f3 con la presencia de acad\u00e9micos\/as interesados\/as en este tema y tambi\u00e9n con la participaci\u00f3n de estudiantes de pre y posgrado. Actualmente estamos en conversaciones con el Ministerio de Justicia para entregarles la evidencia recopilada y recomendaciones para la implementaci\u00f3n de pol\u00edticas publicas que garanticen el respeto incondicional por los Derechos Humanos en Chile.\r\n\r\nAdem\u00e1s, recientemente, nos adjudicamos el siguiente proyecto Fondecyt Regular, en el cual soy coinvestigadora para seguir avanzando en esta l\u00ednea de investigaci\u00f3n: Proyecto Fondecyt Regular (1221805; 2022 a 2025). From compliance to resistance: How do citizens in Chile relate to and position themselves towards the police?. Investigadora Principal: Monica Gerber (UDP).[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2020 - Diciembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26026\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Dise\u00f1o de asignaturas innovadoras para la formaci\u00f3n inicial docente en pedagog\u00eda matem\u00e1tica y desarrollo de un modelo para su evaluaci\u00f3n y mejora.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26026\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26026\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26027\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Dise\u00f1os de estudios de caso para diagnosticar en las carreras de pedagog\u00eda de la Escuela de Educaci\u00f3n y fortalecer en pedagog\u00eda en matem\u00e1tica, la competencia reflexiva y observaci\u00f3n de estudiantes de pr\u00e1ctica II.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26027\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26027\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto aporta al logro del perfil de egreso de las carreras de pedagog\u00eda y en espec\u00edfico en pedagog\u00eda en matem\u00e1tica en los siquientes aspetos:\r\nEntrega insumos para fortalecer el desarrollo de los cursos de pr\u00e1ctica II y a su vez diagnosticar la competencia reflexiva y observaci\u00f3n en el desarrollo de dicho curso. Esto permite a cada carrera orientar de manera oportuna en casos que se requiera, las posteriores actividades pr\u00e1cticas para potenciar la competencia reflexiva y observaci\u00f3n sobre la pr\u00e1ctica del otro.\r\nAporta a que los profesores y profesoras de matem\u00e1tica de la UOH cuenten con competencias s\u00f3lidas, tanto en la competencia reflexiva como en la observaci\u00f3n de clases, lo que permiten posteriormente conducir de mejor manera procesos de ense\u00f1anza-aprendizaje en diversos contextos.\r\nLos casos dise\u00f1ados permiten que en el curso practica II se fortalezcan las oportunidades para la adquisici\u00f3n, desarrollo y aplicaci\u00f3n de conocimiento disciplinares y pedag\u00f3gicos por medio de la reflexi\u00f3n sobre la pr\u00e1ctica del otro y utilizando dimensiones espec\u00edficas para la observaci\u00f3n videos de clases de educaci\u00f3n media. Estas dimensiones espec\u00edfcas est\u00e1n centradas en la gesti\u00f3n general de la clases, y el desarrollo, observaci\u00f3n y reflexi\u00f3n sobre las habilidades de representar y resoluci\u00f3n de problemas propuestas por el MINEDUC en sus bases curriculares (2012).\r\nEl profesor o profesora de matem\u00e1tica de la UOH, debe demostrar un inter\u00e9s y esfuerzo constante por innovar y mejorar la calidad de su docencia, por tanto el proyecto es relevante en este punto, ya que la pr\u00e1ctica II es un nivel intermedio de los cursos de pr\u00e1cticas tempranas, lo que da la posibilidad de proponer mejoras que pueden ser aplicables en asignaturas posteriores (practica III), donde el foco esta puesto sobre el dise\u00f1o, implementaci\u00f3n y evaluaci\u00f3n de actividades de ense\u00f1anza. Adem\u00e1s se espera que el presente proyecto genere la continuidad sobre las habilidades de modelar y argumentar-comunicar, que se terminan de desarrollan en los semestres finales de su formaci\u00f3n.\r\nEl MINEDUC plantea en sus Est\u00e1ndares Orientadores para las carreras de Pedagog\u00eda en Educaci\u00f3n Med\u00eda (2012), est\u00e1ndares pedag\u00f3gicos y disciplinares. En el est\u00e1ndar 10 de conocimientos pedag\u00f3gicos menciona que \u0093Aprende de forma cont\u00ednua y reflexiona sobre su pr\u00e1ctica y su inserci\u00f3n en el sistema educacional\u0094, lo que se manifiesta cuando \u0093Analiza cri&#769;ticamente su pra&#769;ctica pedago&#769;gica y la de otros docentes en funcio&#769;n de su impacto en el aprendizaje de los estudiantes, y propone y fundamenta cambios para mejorarla, utilizando herramientas para observacio&#769;n y evaluacio&#769;n de clases\u0085\u0094. Por lo tanto, el presente proyecto potencia el uso de una herramienta para observaci\u00f3n de clases que son los casos y pautas de observaci\u00f3n, promueve la competencia reflexiva por medio de la revisi\u00f3n de video y casos escritos y finlamente entrega la posibilidad de que los futuros profesores de la UOH reconstruyan y propongan mejoras a las o sus futuras pr\u00e1cticas de ense\u00f1anza.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2020 - Diciembre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26028\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Percepci\u00f3n del desarrollo de competencias de estudiantes de pedagog\u00eda en matem\u00e1ticas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26028\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26028\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La pregunta que gu\u00eda esta investigaci\u00f3n es: \u00bfC\u00f3mo perciben los estudiantes de Pedagog\u00eda en Matem\u00e1tica su desarrollo de competencias docentes relativas a la ense\u00f1anza y el aprendizaje de la Matem\u00e1tica y qu\u00e9 oportunidades consideran que les ha brindado su programa de formaci\u00f3n para desarrollar dichas competencias? \r\n\r\nEl objetivo general es estudiar la autopercepci\u00f3n de la eficacia que tienen los estudiantes de Pedagog\u00eda en Matem\u00e1tica de cuatro universidades chilenas, acerca de su desarrollo de competencias docentes relacionadas con la ense\u00f1anza y el aprendizaje de la Matem\u00e1tica y de las oportunidades que su programa de formaci\u00f3n les ha dado para lograr desarrollar dichas competencias.\r\n\r\nEste objetivo general se abordar\u00e1 a partir de los siguientes objetivos espec\u00edficos:\r\n\r\n&#9679;\tDise\u00f1ar y validar un cuestionario de autopercepci\u00f3n del desarrollo de competencias docentes relativas al aprendizaje y la ense\u00f1anza de la Matem\u00e1tica.\r\n&#9679;\tAnalizar la autopercepci\u00f3n de los estudiantes de Pedagog\u00eda en Matem\u00e1tica de cuatro universidades chilenas acerca del desarrollo de sus competencias docentes.\r\n&#9679;\tAnalizar las oportunidades de desarrollo de competencias docentes que los estudiantes de esas cuatro universidades chilenas atribuyen a sus programas de formaci\u00f3n.\r\nEl primero de los objetivos espec\u00edficos se abordar\u00e1 en la primera etapa del proyecto, centrada en la construcci\u00f3n de un instrumento que permita obtener informaci\u00f3n de calidad en este y otros procesos. Los otros dos objetivos ser\u00e1n tratados en la tercera y \u00faltima etapa, una vez recogidos los datos necesarios.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2020 - Diciembre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26137\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Efecto de la ingesta de alimentos en la tasa de oxidaci\u00f3n de grasas durante ejercicio en sujetos con exceso de peso: \u00bfqu\u00e9 es mejor ingerir antes\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26137\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26137\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2020 - Diciembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26198\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Dise\u00f1o de asignaturas innovadoras para la formaci\u00f3n inicial docente en pedagog\u00eda matem\u00e1tica y desarrollo de un modelo para su evaluaci\u00f3n y mejora.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26198\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26198\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> Proyecto Fondecyt Regular. 1200643<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2020 - Septiembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26233\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Sensory specific satiety in pigs: Feed variety as a strategy to improve animals\u0092 performance and welfare in intensive farming.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26233\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26233\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto Fondecyt Regular. 1200643[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2020 - Febrero 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26338\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Wave-vortex interaction\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26338\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26338\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]In this project, we plan to study the hydrodynamic wave-vortex interaction problem from an experimental point of view using different setups. The aim is to gain further understanding about the influence of vorticity on the propagation of waves and, to a lesser extend, to study how the vorticity field is modified by the presence of waves. Specifically, we plan to study the influence of a vortex field on a sloshing wave, to track the wave scattering, damping and dissipation. Then, we will study the influence of vorticity on wave-turbulence, in order to see how the wave statistics (wave spectrum, height distributions) and properties (dispersion relation, dissipation mechanisms) are affected by vorticity. Finally we will study how an array of vortices induced by a Kelvin-Helmholtz instability can generate surface waves and the back-reaction of the waves on the vortices. The proposed research is based on the collaboration efforts from the long- standing scientific relation between french and chilean experimental nonlinear laboratories: the Matter-out-of- equilibrium laboratory (LMFE) of the Physics Department from the Universidad de Chile and the Nonlinear Physics group from the Laboratoire de Physique Statistique de l''Ecole Normale Sup\u00e9rieure de Paris, France. The expected outcomes of this proposal are: i) to consolidate and expand our french collaboration network including new research labotarories (Laboratoire de Mati\u00e8re et Syst\u00e8mes Compl\u00e8xes, Paris, France and Laboratoire des \u00c9coulements G\u00e9ophysiques et Industriels, Universit\u00e9 de Grenoble-Alpes, Grenoble, France), ii) to co-sign two (2) research publications in Q1 journals, iii) to train postdocs and graduate students in experimental acoustical and optical techniques to measure temporal or spatiotemporal surface wave deformations.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2020 - Diciembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26573\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Dise\u00f1o de asignaturas innovadoras para la formaci\u00f3n inicial docente en pedagog\u00eda matem\u00e1tica y desarrollo de un modelo para su evaluaci\u00f3n y mejora.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26573\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26573\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2020 - Diciembre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26574\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Percepci\u00f3n del desarrollo de competencias de estudiantes de pedagog\u00eda en matem\u00e1ticas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26574\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26574\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La pregunta que gu\u00eda esta investigaci\u00f3n es: \u00bfC\u00f3mo perciben los estudiantes de Pedagog\u00eda en Matem\u00e1tica su desarrollo de competencias docentes relativas a la ense\u00f1anza y el aprendizaje de la Matem\u00e1tica y qu\u00e9 oportunidades consideran que les ha brindado su programa de formaci\u00f3n para desarrollar dichas competencias? \r\n\r\nEl objetivo general es estudiar la autopercepci\u00f3n de la eficacia que tienen los estudiantes de Pedagog\u00eda en Matem\u00e1tica de cuatro universidades chilenas, acerca de su desarrollo de competencias docentes relacionadas con la ense\u00f1anza y el aprendizaje de la Matem\u00e1tica y de las oportunidades que su programa de formaci\u00f3n les ha dado para lograr desarrollar dichas competencias.\r\n\r\nEste objetivo general se abordar\u00e1 a partir de los siguientes objetivos espec\u00edficos:\r\n\r\n&#9679;\tDise\u00f1ar y validar un cuestionario de autopercepci\u00f3n del desarrollo de competencias docentes relativas al aprendizaje y la ense\u00f1anza de la Matem\u00e1tica.\r\n&#9679;\tAnalizar la autopercepci\u00f3n de los estudiantes de Pedagog\u00eda en Matem\u00e1tica de cuatro universidades chilenas acerca del desarrollo de sus competencias docentes.\r\n&#9679;\tAnalizar las oportunidades de desarrollo de competencias docentes que los estudiantes de esas cuatro universidades chilenas atribuyen a sus programas de formaci\u00f3n.\r\nEl primero de los objetivos espec\u00edficos se abordar\u00e1 en la primera etapa del proyecto, centrada en la construcci\u00f3n de un instrumento que permita obtener informaci\u00f3n de calidad en este y otros procesos. Los otros dos objetivos ser\u00e1n tratados en la tercera y \u00faltima etapa, una vez recogidos los datos necesarios.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2020 - Diciembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27107\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27107\" aria-expanded=\"false\" aria-controls=\"collapse-27107\">\n                                            Concurso interno de Innovaci\u00f3n Cient\u00edfica y Tecnol\u00f3gica Universidad de Los Lagos: \u0093Plataforma LMS Tecnolog\u00eda para promover el liderazgo de nuevas juventudes femeninas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27107\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27107\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Crear una plataforma digital LMS que promueva el liderazgo en ni\u00f1as y mujeres adolescentes, para que la tecnolog\u00eda sea un medio activo que fortalezca las capacidades y participaci\u00f3n de ni\u00f1as y mujeres adolescentes en sus comunidades y futuros profesionales de la region de Los Lagos.\r\nObjetivo espec\u00edfico 1:\r\nIdentificar el contenido y las funcionalidades de la plataforma, a trav\u00e9s del proceso de conocer cu\u00e1les son las necesidades y dificultades de ni\u00f1as y mujeres adolescentes para desarrollar liderazgos en sus comunidades y futuro profesional.\r\nAcci\u00f3n: encuestas y entrevistas a ni\u00f1as y mujeres adolescentes de la regi\u00f3n de Los Lagos\r\nObjetivo espec\u00edfico 2:\r\nConocer modelos de gesti\u00f3n virtuales y plataformas educativas digitales que promuevan el liderazgo de ni\u00f1as y mujeres adolescentes y sus participaciones y producciones en el \u00e1rea social y profesional. Acci\u00f3n: estudio de plataformas nacionales e internacionales, entrevistas a creadores\/as de dichos modelos y plataformas.\r\nObjetico espec\u00edfico 3:\r\nDise\u00f1ar e implementar una plataforma LMS o Moodle que permita a ni\u00f1as y mujeres adolescentes interactuar, conocer contenidos y beneficios sobre el liderazgo, experiencias de otras mujeres y entregue orientaciones sobre su participaci\u00f3n en el mundo social y laboral.\r\nAcci\u00f3n: dise\u00f1ar y crear LMS o Moodle en sitio www.lideresaschile.cl\r\nObjetivo 4: Difundir la plataforma para conocer los aspectos de mejora. Acci\u00f3n: Actividad de difusi\u00f3n y desarrollo de encuesta a las usuarias de la plataforma.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Febrero 2020 - Diciembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26482\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Exclusi\u00f3n del ganado durante el periodo estacional en Santuario de la Naturaleza Los Nogales: controlando pasivamente la erosi\u00f3n de la vegetaci\u00f3n y suelo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26482\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26482\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Existen dos tipos de restauraci\u00f3n ecol\u00f3gica: activa y pasiva. La primera se refiere a la recuperaci\u00f3n artificial del sistema, mediante un programa de introducci\u00f3n y manejo de especies simulando la sucesi\u00f3n natural. Este tipo de restauraci\u00f3n es muy conveniente en aquellas \u00e1reas donde el ecosistema no es capaz de recuperarse naturalmente y se requiere la intervenci\u00f3n del hombre, que a priori, no ser\u00eda el caso del SNLN. Mientras que la Restauraci\u00f3n pasiva se refiere a la recuperaci\u00f3n natural del sistema, sin intervenci\u00f3n o con un manejo m\u00ednimo. Este tipo de restauraci\u00f3n se recomienda cuando no hay medios econ\u00f3micos o hay dificultades log\u00edsticas para recuperar \u00e1reas que son relativamente grandes, como es el caso del SNLN. El principio b\u00e1sico de este tipo de restauraci\u00f3n es dejar que el sistema siga su curso natural de recolonizaci\u00f3n de especies nativas, d\u00e1ndole un m\u00ednimo impulso. Por lo tanto, actividades de restauraci\u00f3n pasiva, como el cercado, pueden tener un efecto positivo sobre las condiciones de sitio y micrositio. El cercado reduce la presi\u00f3n de agentes de degradaci\u00f3n como el ganado mayor, lo que favorece la regeneraci\u00f3n, el aumento de la cobertura vegetal y la fijaci\u00f3n de nutrientes en el suelo.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> SA19I0106<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2020 - Diciembre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27084\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Validaci\u00f3n del Test del Escal\u00f3n para medir la condici\u00f3n f\u00edsica en ni\u00f1os, ni\u00f1as y adolescentes\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27084\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27084\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"].[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2020 - Diciembre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26038\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Escolarizaci\u00f3n de la educaci\u00f3n parvularia en Chile: definici\u00f3n, causas y proposiciones en la visi\u00f3n de las comunidades educativas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26038\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26038\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto tiene como objetivo general explorar la visi\u00f3n de distintos actores de las comunidades educativas sobre la escolarizaci\u00f3n de la educaci\u00f3n parvularia en Chile. Sus objetivos espec\u00edficos son: (1) Identificar significados con que distintos actores de las comunidades educativas definen la escolarizaci\u00f3n de la educaci\u00f3n parvularia en Chile; (2) Identificar factores que distintos actores de las comunidades educativas perciben como causas de la escolarizaci\u00f3n de la educaci\u00f3n parvularia en Chile; (3) Identificar proposiciones que distintos actores de las comunidades educativas plantean con respecto a la escolarizaci\u00f3n de la educaci\u00f3n parvularia.\r\nLa metodolog\u00eda se basa en un dise\u00f1o cualitativo de nivel exploratorio, definiendo una muestra intencionada de 6 jardines infantiles y 6 escuelas financiados con recursos p\u00fablicos que impartan Nivel Medio y\/o Nivel Transici\u00f3n. Dentro de cada establecimiento participan tres distintos actores, con el fin de obtener una visi\u00f3n global de cada uno: director, l\u00edder pedag\u00f3gico del nivel, y educadoras de p\u00e1rvulos (dado el contexto de pandemia, no fue viable obtener acceso a apoderados). Adem\u00e1s (en reemplazo de apoderados), participan autoridades y ex-autoridades nacionales del nivel. Los datos fueron recolectados mediante entrevistas semi-estructuradas individuales, realizadas de forma remota, y est\u00e1n siendo analizados mediante an\u00e1lisis de contenido basado en el m\u00e9todo de comparaci\u00f3n constante.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2020 - Diciembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26649\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Stochastic Optimization and Chance Constraints with Applications to Energy (SOCCAE)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26649\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26649\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Stochastic Optimization and Chance Constraints with Applications to Energy (SOCCAE)[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26669\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            OH-TARGET (One Health Training and Research Global Network)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26669\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26669\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Global health cannot be viewed in isolation; it is \"dependent on a person's living environment, on factors such as education, the environment, climate, water and food\" (BMZ Position 02\/2019: Global health, an investment in the future). The One Health approach involves the \"development and implementation of programmes, policies, laws and research in which multiple sectors communicate and collaborate to achieve better public health outcomes\" \/https:\/\/www.who.int\/features\/qa\/one-health\/en\/). The overall objective is to improve global health conditions by understanding the structural health problems caused by the living environment and developing context-specific approaches in a holistic and participatory approach to development cooperation with a focus on education and training. Research serves above all as a means of imparting research competence. The network uses competence-based pedagogy and activating learning methods developed in the past within the framework of the Center for International Health (CIHLMU), expands them, and uses ICT-based learning methods.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> Resoluci\u00f3n exenta N\u00b0 2626, 16 de diciembre de 2019<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2019 - Junio 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Desarrollo Social y Familia, Chile<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26666\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Capacitaci\u00f3n Nacional para equipos de trabajo con personas en situaci\u00f3n de calle con discapacidad.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26666\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26666\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]\"Convocatoria Capacitaci\u00f3n Nacional para equipos de trabajo con personas en situaci\u00f3n de\r\ncalle con discapacidad\" del Programa Tr\u00e1nsito a la Vida Independiente, 2019. \r\n\r\nEl presente proyecto fue adjudicado tras proceso de licitaci\u00f3n publica nacional. Resoluci\u00f3n exenta N\u00b0 2626, 16 de diciembre de 2019\r\n\r\nPara la ejecuci\u00f3n de esta propuesta, nuestro equipo propuso una modalidad presencial en las 16 regiones del pa\u00eds con una duraci\u00f3n de 8 horas cronol\u00f3gicas. El enfoque previsto est\u00e1 basado en una metodolog\u00eda de aprendizaje constructivista y dialogante, con el fin de capacitar y fortalecer significativamente a los equipos que trabajan en el Programa de Vida Independiente.\r\n\r\nA trav\u00e9s de este trabajo se capacit\u00f3 desde la Universidad de O'Higgins a todos los equipos del pa\u00eds de cada una de las regiones. Permitiendo vinculaci\u00f3n activa con el territorio y fortaleciendo redes para el trabajo territorial de mi l\u00ednea de investigaci\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> Resoluci\u00f3n exenta N\u00b0 2626, 16 de diciembre de 2019<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2019 - Junio 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Desarrollo Social y Familia, Chile<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26822\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Capacitaci\u00f3n Nacional para equipos de trabajo con personas en situaci\u00f3n de calle con discapacidad.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26822\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26822\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]\"Convocatoria Capacitaci\u00f3n Nacional para equipos de trabajo con personas en situaci\u00f3n de\r\ncalle con discapacidad\" del Programa Tr\u00e1nsito a la Vida Independiente, 2019. \r\n\r\nEl presente proyecto fue adjudicado tras proceso de licitaci\u00f3n publica nacional. Resoluci\u00f3n exenta N\u00b0 2626, 16 de diciembre de 2019\r\n\r\nPara la ejecuci\u00f3n de esta propuesta, nuestro equipo propuso una modalidad presencial en las 16 regiones del pa\u00eds con una duraci\u00f3n de 8 horas cronol\u00f3gicas. El enfoque previsto est\u00e1 basado en una metodolog\u00eda de aprendizaje constructivista y dialogante, con el fin de capacitar y fortalecer significativamente a los equipos que trabajan en el Programa de Vida Independiente.\r\n\r\nA trav\u00e9s de este trabajo se capacit\u00f3 desde la Universidad de O'Higgins a todos los equipos del pa\u00eds de cada una de las regiones. Permitiendo vinculaci\u00f3n activa con el territorio y fortaleciendo redes para el trabajo territorial de mi l\u00ednea de investigaci\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2019 - Diciembre 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26091\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            First Japan-Chile Symposium in Field Robotics\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26091\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26091\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ID19I10001<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2019 - Febrero 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26936\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26936\" aria-expanded=\"false\" aria-controls=\"collapse-26936\">\n                                            Desarrollo de un modelo 3D de reservas de agua subterr\u00e1nea en una plataforma web para mejorar la toma de decisi\u00f3n durante sequias en el rio Limar\u00ed\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26936\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26936\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo general: mejorar la toma de decisiones respecto al manejo de los recursos h\u00eddricos subterr\u00e1neos durante sequias mediante una plataforma web en acceso libre con un modelo 3D de las reservas de agua subterr\u00e1nea en la Cuenca del Limari. Objetivos espec\u00edficos: (i) crear un modelo 3D de los acu\u00edferos del valle del Limar\u00ed a trav\u00e9s de sondajes de resonancia magn\u00e9tica; (ii) desarrollar una plataforma web de acceso libre con el modelo 3D, sus productos asociados como mapa de reservas y costo de extracci\u00f3n, medidas de mitigaci\u00f3n de la sequ\u00eda, capas de informaciones sobre derechos de agua y perforaci\u00f3n, y un foro para que los usuarios suban informaciones; (iii) capacitar a los usuarios finales y tomadores de decisiones en la utilizaci\u00f3n de la plataforma.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2019 - Octubre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26283\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Implementaci\u00f3n de un programa de monitoreo de plaguicidas en agua de riego y hortalizas de consumo en fresco en la Regi\u00f3n de O&#8217;Higgins; PAI N\u00b0 77190023\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26283\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26283\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2019 - Octubre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25993\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Exercise stimulates autophagy by downregulation of NOX2 activity improving young and aged human skeletal muscle function\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25993\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25993\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]During the past few decades average life expectancy has dramatically increased worldwide; specifically by 2050 the number of older adults will overcome the number of young people in Chile. This leads to a major challenge due to multiple chronic diseases highly prevalent in elderly. Aging process is defined as a series of time-dependent physiological changes that decrease reserve and functional capacity of skeletal muscle. Several studies have proposed that aging is caused by damage of macromolecules by reactive oxygen species (ROS) and decreased autophagy levels, a process that is essential for skeletal muscle regeneration, homeostasis and function. Exercise is a novel strategy used in elderly, which has shown to improve muscle mass, muscle function and decrease chronic diseases in old individuals. However, the molecular mechanisms and signaling pathways involved on the benefits of exercise in aged skeletal muscle are not completely clear. While exercise regulations of oxidative stress and autophagy have been studied separately, a direct interplay between exercise inducing autophagy via a ROS-dependent pathway has not yet been addressed in young or aged human skeletal muscle. Moreover, studies in human skeletal muscle examining the autophagy modulation after endurance exercise are limited and controversial. Although it is known that resting autophagy levels are decreased in aged skeletal muscle, the effects of acute exercise on skeletal muscle autophagy between young and older adults remain to be elucidated and could shed light on regulation of autophagy in humans. Additionally, it is also not known if a controlled exercise-training program can induce similar increases in autophagy levels in older adults. Recently, we have shown that the non-mitochondrial sources of ROS, NADPH oxidases 2 (NOX2), plays a major role in ROS production in skeletal muscle, both at rest and during contracting activity. Furthermore, our preliminary results show that NOX2 expression is increased during the aging process and strongly correlates with decreased autophagy levels detected in aged human skeletal muscle. Moreover, we also show that 12 weeks of endurance exercise training reduced the NOX2 levels in aged human muscle. We speculate that a decrease in NOX2 associated with a decrease in ROS levels in aged skeletal muscle induced by exercise training will improve aged muscle function by re-stablishing autophagy up to young skeletal muscle levels[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ID19I10050<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2019 - Diciembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26029\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Evaluaci\u00f3n diagn\u00f3stica inicial en pedagog\u00eda: construcci\u00f3n colaborativa de instrumentos para una mejor formaci\u00f3n docente\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26029\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26029\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo General:\r\nGenerar colaborativamente un conjunto de instrumentos de evaluaci\u00f3n diagn\u00f3stica inicial para carreras de pedagog\u00eda en ense\u00f1anza b\u00e1sica, que eval\u00faen habilidades esenciales del buen desempe\u00f1o profesional docente, a fin de mejorar los procesos formativos conducentes al logro de los perfiles de egreso de las instituciones formadoras, y que cumplan est\u00e1ndares t\u00e9cnicos de calidad en medici\u00f3n.\r\n\r\nObjetivos Espec\u00edficos:\r\n\r\n1. Desarrollar y adaptar instrumentos que eval\u00faen habilidades caracter\u00edsticas del buen desempe\u00f1o docente seg\u00fan la literatura cient\u00edfica.\r\n2. Implementar estudios emp\u00edricos cuantitativos y cualitativos en muestras de estudiantes de pedagog\u00eda b\u00e1sica que permitan garantizar el cumplimiento de est\u00e1ndares t\u00e9cnicos de medici\u00f3n (evidencias de validez, confiabilidad).\r\n3. Explorar la relaci\u00f3n de las habilidades evaluadas con los instrumentos con oportunidades de formaci\u00f3n y con la experiencia acad\u00e9mica y pr\u00e1ctica acumulada por los estudiantes de pedagog\u00eda.\r\n4. Formalizar la asociaci\u00f3n institucional involucrada en el[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2019 - Noviembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26050\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fondecyt de Iniciaci\u00f3n\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26050\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26050\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ID19I10050<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2019 - Diciembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26161\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Evaluaci\u00f3n diagn\u00f3stica inicial en pedagog\u00eda: construcci\u00f3n colaborativa de instrumentos para una mejor formaci\u00f3n docente\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26161\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26161\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo General:\r\nGenerar colaborativamente un conjunto de instrumentos de evaluaci\u00f3n diagn\u00f3stica inicial para carreras de pedagog\u00eda en ense\u00f1anza b\u00e1sica, que eval\u00faen habilidades esenciales del buen desempe\u00f1o profesional docente, a fin de mejorar los procesos formativos conducentes al logro de los perfiles de egreso de las instituciones formadoras, y que cumplan est\u00e1ndares t\u00e9cnicos de calidad en medici\u00f3n.\r\n\r\nObjetivos Espec\u00edficos:\r\n\r\n1. Desarrollar y adaptar instrumentos que eval\u00faen habilidades caracter\u00edsticas del buen desempe\u00f1o docente seg\u00fan la literatura cient\u00edfica.\r\n2. Implementar estudios emp\u00edricos cuantitativos y cualitativos en muestras de estudiantes de pedagog\u00eda b\u00e1sica que permitan garantizar el cumplimiento de est\u00e1ndares t\u00e9cnicos de medici\u00f3n (evidencias de validez, confiabilidad).\r\n3. Explorar la relaci\u00f3n de las habilidades evaluadas con los instrumentos con oportunidades de formaci\u00f3n y con la experiencia acad\u00e9mica y pr\u00e1ctica acumulada por los estudiantes de pedagog\u00eda.\r\n4. Formalizar la asociaci\u00f3n institucional involucrada en el[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ID19I10050<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2019 - Diciembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26201\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Evaluaci\u00f3n diagn\u00f3stica inicial en pedagog\u00eda: construcci\u00f3n colaborativa de instrumentos para una mejor formaci\u00f3n docente\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26201\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26201\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo General:\r\nGenerar colaborativamente un conjunto de instrumentos de evaluaci\u00f3n diagn\u00f3stica inicial para carreras de pedagog\u00eda en ense\u00f1anza b\u00e1sica, que eval\u00faen habilidades esenciales del buen desempe\u00f1o profesional docente, a fin de mejorar los procesos formativos conducentes al logro de los perfiles de egreso de las instituciones formadoras, y que cumplan est\u00e1ndares t\u00e9cnicos de calidad en medici\u00f3n.\r\n\r\nObjetivos Espec\u00edficos:\r\n\r\n1. Desarrollar y adaptar instrumentos que eval\u00faen habilidades caracter\u00edsticas del buen desempe\u00f1o docente seg\u00fan la literatura cient\u00edfica.\r\n2. Implementar estudios emp\u00edricos cuantitativos y cualitativos en muestras de estudiantes de pedagog\u00eda b\u00e1sica que permitan garantizar el cumplimiento de est\u00e1ndares t\u00e9cnicos de medici\u00f3n (evidencias de validez, confiabilidad).\r\n3. Explorar la relaci\u00f3n de las habilidades evaluadas con los instrumentos con oportunidades de formaci\u00f3n y con la experiencia acad\u00e9mica y pr\u00e1ctica acumulada por los estudiantes de pedagog\u00eda.\r\n4. Formalizar la asociaci\u00f3n institucional involucrada en el[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FONDEF ID19I10030<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2019 - Agosto 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26202\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            FONDEF IDeA Modelo de ense\u00f1anza para fortalecer el pensamiento matem\u00e1tico en el nivel de transici\u00f3n de la educaci\u00f3n parvularia (id19i10030)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26202\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26202\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Evaluaciones recientes de los entornos de aprendizaje chilenos han determinado que las dimensiones m\u00e1s deficientes en Educaci\u00f3n Parvularia son aquellas relacionadas con la calidad de las oportunidades de aprendizaje, actividades creativas y oportunidades de juego. Esto es particularmente cierto para actividades dirigidas a fortalecer los aprendizajes matem\u00e1ticos, las cuales se realizan (en promedio) apenas 15 minutos al d\u00eda y generalmente no fortalecen el dominio y comprensi\u00f3n de los procesos matem\u00e1ticos, sino que priorizan el trabajo mec\u00e1nico y procedimental contribuyendo escasamente al fortalecimiento del pensamiento matem\u00e1tico complejo. Este proyecto va dirigido a mejorar la calidad de estos aprendizajes en el nivel de transici\u00f3n de la Educaci\u00f3n Parvularia. Aqu\u00ed se plantea el desarrollo de un modelo de ense\u00f1anza soportado en dos herramientas tecnol\u00f3gicas integradas: un conjunto de materiales concretos, representacionales y abstractos (CRA) que permita a los docentes dise\u00f1ar experiencias de aprendizajes matem\u00e1ticos de alta calidad y un software para realizar evaluaciones automatizadas de los objetivos de aprendizaje del pensamiento matem\u00e1tico (OAPM) utilizando tareas en formato de actividades l\u00fadicas y juegos computarizados. \r\nAbundante literatura internacional ha demostrado que la estimulaci\u00f3n de habilidades como el procesamiento espacial y el razonamiento anal\u00f3gico fortalece las habilidades l\u00f3gico-num\u00e9ricas y tienen efectos positivos en los desempe\u00f1os matem\u00e1ticos posteriores. En este contexto, estudios recientes realizados por nuestro equipo han delineado algunas maneras en que el razonamiento anal\u00f3gico y el procesamiento espacial se pueden explotar en el dise\u00f1o de materiales y estrategias efectivas para ense\u00f1ar matem\u00e1ticas. Este proyecto busca aplicar estas investigaciones al dise\u00f1o de materiales CRA y evaluaciones informatizadas del modelo de ense\u00f1anza propuesto. La hip\u00f3tesis de desarrollo es que la utilizaci\u00f3n de este modelo de ense\u00f1anza en las aulas incrementar\u00e1 significativamente los aprendizajes matem\u00e1ticos de los ni\u00f1os y la calidad de las pr\u00e1cticas pedag\u00f3gicas de los docentes. \r\nEn este proyecto se desarrolla una prueba de concepto del modelo de ense\u00f1anza para verificar si su utilizaci\u00f3n en las aulas es viable y tiene efectos ben\u00e9ficos en los aprendizajes de los ni\u00f1os y las pr\u00e1cticas pedag\u00f3gicas de los docentes. Nuestro equipo de investigadores dise\u00f1ar\u00e1 un prototipo del conjunto de materiales CRA y encargar\u00e1 la manufactura de \u00e9stos a una empresa externa. Durante este proyecto tambi\u00e9n se desarrollar\u00e1 una versi\u00f3n piloto de un instrumento computarizado que permita evaluar los OAPM de manera automatizada utilizando tareas en formato de actividades l\u00fadicas y juegos. Para verificar que el uso de estos materiales en las aulas incrementa los aprendizajes matem\u00e1ticos se realizar\u00e1 una intervenci\u00f3n escolar controlada en alrededor de 10 aulas de prek\u00ednder, reclutando al menos 300 participantes. Esta intervenci\u00f3n tiene un dise\u00f1o experimental, que controla el efecto del profesor y con l\u00ednea base (pretest-postest). Algunas variables de desarrollo cognitivo y manejo del lenguaje de los ni\u00f1os se medir\u00e1n para realizar controles estad\u00edsticos en el an\u00e1lisis de datos. El incremento en la calidad de las pr\u00e1cticas pedag\u00f3gicas ser\u00e1 determinado mediante el an\u00e1lisis de registros audiovisuales obtenidos durante la intervenci\u00f3n escolar, los cuales ser\u00e1n codificados y analizados acorde a un instrumento bien conocido en la literatura internacional.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2019 - Octubre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26274\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Experiments on Fluid Impact: the example of bottle\u0096flip challenge\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26274\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26274\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][proyecto ejecutado en 4 a\u00f1os, por haberse acogido a extensi\u00f3n de pandemia]\r\n\r\nFluid impacts are present in a large variety of situations. For instance, the craters formed by rain--drops impacting the soil are relevant in agricultural applications. Also, wave--impact can damage coastal structures, and impact of sloshing--waves may produce over--turning of trucks or vessels that transport fluids. Therefore, the relevance (I would say the impact) of fluid impact goes from industry to environmental sciences. And also because of its beauty and scientific challenges, fluid impact is currently (and largely) studied by communities of physicist and applied mathematicians.\r\n\r\nAs the field of fluid impact is vast, we focus in one particular problem: the bottle flip challenge, as (1) it provides more contoured problems to be tackled experimentally during the time limits of this proposal; (2) it could give insights about other relevant and applied problems; (3) as it already received press coverage worldwide, it is likely to have a large visibility of the results obtained.\r\n\r\nThe bottle flip challenge is a game consisting in spinning a plastic bottle partially filled with water, in order to make it landing vertically after completing a single turn, or more. In recent years the challenge received huge attention in social media and some press coverage including Las Ultimas Noticias. In our opinion, such effervescence for a physical phenomenon relies in the counter-intuitiveness of the trick: as the bottle is turning, one expect it to continue turning until falling down, instead of the abrupt and stable stop in a vertical position that actually occurs.  \r\nSome of the videos, magazine publication and the available physics article (Dekker et al., 2018), focus their attention in the conservation of angular momentum and the variations of momentum of inertia to explain the successful landing. Dekker et al. recognize that the physics of water sloshing is highly complex in itself and approached the problem by the side of classical mechanics. What we propose here, is indeed to take the challenge of fluid dynamics to carry conserved-quantities explanations to a greater depth. \r\n\r\nOur starting point is a high--speed camera recording of a successful throw and landing. There, one can observe at least two key fluid-dynamical events that contribute to the vertical stabilization of the bottle: (1) the impact of a water jet into the wall, strongly reducing the bottle-angular-momentum during the free traveling of the system, and (2) a violent redistribution of water taking place at landing, where water captures an important amount of the kinetic energy carried by the bottle. After describing these two key events, we can already summarize this proposal as a committed experimental study of both events, plus an effort to translate these ideas into a (engineering inspired) sloshing dynamics application. \r\n\r\nWe propose first to study the landing stage asking the following question (Question 1): for a container partially filled with fluid, can fluid motion act as a shock-absorber for the impact?\r\nWe propose to perform an experiment where the bottle is rotated on its vertical axis before it is released (also vertically). Then we will study the effect of fluid motion, by simply defining a restitution coefficient (valid at landing impact) and to see when the loss of bottle-energy is maximized. Bottle-energy loss implies fluid-energy absorption: a balance that will be experimentally checked. Maximal loss of bottle-energy indeed ensures greater bottle stability at landing. \r\n\r\nThen, we will focus on the effect of water--jet--impact asking Question 2: On which circumstances jet-impact may stabilize a freely rotating container?\r\nOn one side, we will perform experiments of bottle throwing just as the challenge proposes (that is, throwing the bottle by hand). Also, we will construct a quasi-2D experiment, to perform computer-controlled rotations of the bottle in order to produce jet--impact on the bottle walls. In both cases, we will study angular momentum transfer and deviations from bottles without impact by filming with a high-speed camera and applying mass conservation models.\r\n\r\nIn order to return to the general problem of fluid impact, our final question (3) is Can we take advantage of jet-impact to stabilize any moving container?\r\nHere we will apply the previous knowledge to the study a classical configuration exhibiting wave impact: a container subjected to horizontal excitation. After characterizing impact conditions in the solid container, we will study the consequences (in wall acceleration for instance) of having a freely moving wall.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2019 - Octubre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26302\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Exposure of infants to mycotoxins through cereal consumption: a risk assessment approach\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26302\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26302\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]ealizar un modelo de estimaci\u00f3n de exposici\u00f3n a micotoxinas a trav\u00e9s del consumo de cereales para el desayuno en ni\u00f1os peque\u00f1os, a partir de el an\u00e1lisis de las 6 principales micotoxinas en dichos cereales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2019 - Octubre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26389\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Activaci\u00f3n de la inmunidad en frutales del g\u00e9nero Prunus para el potenciamiento de su tolerancia a enfermedades fungosas y bacterianas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26389\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26389\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La Universidad de O\u0092Higgins postula la incorporaci\u00f3n como acad\u00e9mico a la Dra. Lorena Pizarro al Instituto de Ciencias Agron\u00f3micas y Veterinarias. La Dra Pizarro es una investigadora joven, de excelencia acad\u00e9mica, productiva y de alta competitividad, quien cumple a cabalidad con la misi\u00f3n de nuestra Universidad en la generaci\u00f3n y difusi\u00f3n de conocimiento, para el desarrollo la Regi\u00f3n de O\u0092Higgins y el pa\u00eds. Ella es especialista en inmunidad vegetal desempe\u00f1\u00e1ndose actualmente como investigador post-doctoral en Israel, en los laboratorios del Dr Adi Avni (Tel-Aviv University) y la Dra Maya Bar (Volcani Center). La candidata propone el estudio de la respuesta inmune de especies de frutales del g\u00e9nero Prunus, tales como Cerezo, Durazno y nectarines, los cuales son de gran importancia en la producci\u00f3n agr\u00edcola de la regi\u00f3n de O\u0092Higgins y el pa\u00eds. Particularmente, esta propuesta de investigaci\u00f3n plantea el estudio de una novedosa y vers\u00e1til estrategia para la activaci\u00f3n de la inmunidad en frutales del g\u00e9nero Prunus, a trav\u00e9s de la aplicaci\u00f3n de elicitores de origen bacteriano y f\u00fangico. De esta forma, se espera potenciar la tolerancia a pat\u00f3genos en estos frutales, y mejorar los sistemas de control de plagas usados en Chile. Se proyecta que la Dra Pizarro desarrolle esta nueva l\u00ednea de investigaci\u00f3n basada en las necesidades agr\u00edcolas de la regi\u00f3n, fortalezca la masa cr\u00edtica de la fitopatolog\u00eda frut\u00edcola en nuestra instituci\u00f3n, participe de manera transversal en el distintos institutos, mantenga una estrecha colaboraci\u00f3n con la regi\u00f3n a trav\u00e9s de comunicaci\u00f3n directa con el sector agr\u00edcola y Escuelas de la regi\u00f3n a trav\u00e9s de nuestro programa PAR-Explora, establezca colaboraciones nacionales e internacionales, y se adjudique de proyectos de investigaci\u00f3n extramurales, para as\u00ed ser parte del desarrollo y posicionamiento a la Universidad de O\u0092Higgins como una instituci\u00f3n de educaci\u00f3n superior de reconocida calidad a nivel regional, nacional e internacional.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> PAI77190021<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2019 - Octubre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26470\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desarrollo de estrategias de control para problemas de electro-movilidad y eficiencia energ\u00e9tica\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26470\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26470\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Esta Propuesta de Instalaci\u00f3n se da en el contexto de una Universidad nueva que  se encuentra en pleno periodo de conformaci\u00f3n de su planta acad\u00e9mica; el Dr. Diego Mu\u00f1oz Carpintero ser\u00e1 el primer experto en el \u00e1rea de control autom\u00e1tico del Instituto de Ciencias de la Ingenier\u00eda y la Universidad, complementado de este modo la planta docente y de investigaci\u00f3n en Ingenier\u00eda El\u00e9ctrica.\r\n\r\nLa Universidad y el Instituto de Ciencias de la Ingenier\u00eda consideran como aspectos centrales de su misi\u00f3n una vocaci\u00f3n de excelencia acad\u00e9mica y profesional, y de responsabilidad social con un sentido de pertenencia regional. Respecto del \u00faltimo punto, es prioritaria la investigaci\u00f3n relevante para las actividades principales de la regi\u00f3n, minera y agroindustrial, y en tem\u00e1ticas de relevancia local y global, como energ\u00eda, sustentabilidad, y en ciencias f\u00edsicas y matem\u00e1ticas.\r\n\r\nLa selecci\u00f3n del investigador para este concurso cumple todos los criterios de excelencia en investigaci\u00f3n, docencia, y de relevancia de su investigaci\u00f3n en un contexto regional y global. \r\n\r\nLa propuesta de investigaci\u00f3n se centra en temas de electro-movilidad y eficiencia energ\u00e9tica. En particular, abordar\u00e1 problem\u00e1ticas relacionadas con veh\u00edculos el\u00e9ctricos (EVs): ruteo de flotas de EVs para maximizaci\u00f3n de vida \u00fatil de las bater\u00edas, control tolerante a fallas de EVs, dise\u00f1o de estrategias de control de servicios auxiliares brindadas por estaciones de carga de EVs, y el dise\u00f1o y an\u00e1lisis de estrategias de control y optimizaci\u00f3n para estos problemas. La investigaci\u00f3n en estos temas posee relevancia local por su impacto en sustentabilidad y utilidad para las principales actividades econ\u00f3micas de la regi\u00f3n (miner\u00eda y agroindustrial), y tambi\u00e9n poseen relevancia global por enmarcarse en las tendencias globales de conversi\u00f3n al uso de energ\u00edas limpias y eficientes. Finalmente, existen sinergias entre este proyecto de investigaci\u00f3n y el perfil del Dr. Mu\u00f1oz, con otros proyectos y el perfil de otros acad\u00e9micos del Instituto.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ID19I10050<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2019 - Diciembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26575\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Evaluaci\u00f3n diagn\u00f3stica inicial en pedagog\u00eda: construcci\u00f3n colaborativa de instrumentos para una mejor formaci\u00f3n docente\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26575\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26575\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo General:\r\nGenerar colaborativamente un conjunto de instrumentos de evaluaci\u00f3n diagn\u00f3stica inicial para carreras de pedagog\u00eda en ense\u00f1anza b\u00e1sica, que eval\u00faen habilidades esenciales del buen desempe\u00f1o profesional docente, a fin de mejorar los procesos formativos conducentes al logro de los perfiles de egreso de las instituciones formadoras, y que cumplan est\u00e1ndares t\u00e9cnicos de calidad en medici\u00f3n.\r\n\r\nObjetivos Espec\u00edficos:\r\n\r\n1. Desarrollar y adaptar instrumentos que eval\u00faen habilidades caracter\u00edsticas del buen desempe\u00f1o docente seg\u00fan la literatura cient\u00edfica.\r\n2. Implementar estudios emp\u00edricos cuantitativos y cualitativos en muestras de estudiantes de pedagog\u00eda b\u00e1sica que permitan garantizar el cumplimiento de est\u00e1ndares t\u00e9cnicos de medici\u00f3n (evidencias de validez, confiabilidad).\r\n3. Explorar la relaci\u00f3n de las habilidades evaluadas con los instrumentos con oportunidades de formaci\u00f3n y con la experiencia acad\u00e9mica y pr\u00e1ctica acumulada por los estudiantes de pedagog\u00eda.\r\n4. Formalizar la asociaci\u00f3n institucional involucrada en el[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FONDEF ID19I10030<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2019 - Agosto 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26694\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            FONDEF IDeA Modelo de ense\u00f1anza para fortalecer el pensamiento matem\u00e1tico en el nivel de transici\u00f3n de la educaci\u00f3n parvularia (id19i10030)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26694\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26694\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Evaluaciones recientes de los entornos de aprendizaje chilenos han determinado que las dimensiones m\u00e1s deficientes en Educaci\u00f3n Parvularia son aquellas relacionadas con la calidad de las oportunidades de aprendizaje, actividades creativas y oportunidades de juego. Esto es particularmente cierto para actividades dirigidas a fortalecer los aprendizajes matem\u00e1ticos, las cuales se realizan (en promedio) apenas 15 minutos al d\u00eda y generalmente no fortalecen el dominio y comprensi\u00f3n de los procesos matem\u00e1ticos, sino que priorizan el trabajo mec\u00e1nico y procedimental contribuyendo escasamente al fortalecimiento del pensamiento matem\u00e1tico complejo. Este proyecto va dirigido a mejorar la calidad de estos aprendizajes en el nivel de transici\u00f3n de la Educaci\u00f3n Parvularia. Aqu\u00ed se plantea el desarrollo de un modelo de ense\u00f1anza soportado en dos herramientas tecnol\u00f3gicas integradas: un conjunto de materiales concretos, representacionales y abstractos (CRA) que permita a los docentes dise\u00f1ar experiencias de aprendizajes matem\u00e1ticos de alta calidad y un software para realizar evaluaciones automatizadas de los objetivos de aprendizaje del pensamiento matem\u00e1tico (OAPM) utilizando tareas en formato de actividades l\u00fadicas y juegos computarizados. \r\nAbundante literatura internacional ha demostrado que la estimulaci\u00f3n de habilidades como el procesamiento espacial y el razonamiento anal\u00f3gico fortalece las habilidades l\u00f3gico-num\u00e9ricas y tienen efectos positivos en los desempe\u00f1os matem\u00e1ticos posteriores. En este contexto, estudios recientes realizados por nuestro equipo han delineado algunas maneras en que el razonamiento anal\u00f3gico y el procesamiento espacial se pueden explotar en el dise\u00f1o de materiales y estrategias efectivas para ense\u00f1ar matem\u00e1ticas. Este proyecto busca aplicar estas investigaciones al dise\u00f1o de materiales CRA y evaluaciones informatizadas del modelo de ense\u00f1anza propuesto. La hip\u00f3tesis de desarrollo es que la utilizaci\u00f3n de este modelo de ense\u00f1anza en las aulas incrementar\u00e1 significativamente los aprendizajes matem\u00e1ticos de los ni\u00f1os y la calidad de las pr\u00e1cticas pedag\u00f3gicas de los docentes. \r\nEn este proyecto se desarrolla una prueba de concepto del modelo de ense\u00f1anza para verificar si su utilizaci\u00f3n en las aulas es viable y tiene efectos ben\u00e9ficos en los aprendizajes de los ni\u00f1os y las pr\u00e1cticas pedag\u00f3gicas de los docentes. Nuestro equipo de investigadores dise\u00f1ar\u00e1 un prototipo del conjunto de materiales CRA y encargar\u00e1 la manufactura de \u00e9stos a una empresa externa. Durante este proyecto tambi\u00e9n se desarrollar\u00e1 una versi\u00f3n piloto de un instrumento computarizado que permita evaluar los OAPM de manera automatizada utilizando tareas en formato de actividades l\u00fadicas y juegos. Para verificar que el uso de estos materiales en las aulas incrementa los aprendizajes matem\u00e1ticos se realizar\u00e1 una intervenci\u00f3n escolar controlada en alrededor de 10 aulas de prek\u00ednder, reclutando al menos 300 participantes. Esta intervenci\u00f3n tiene un dise\u00f1o experimental, que controla el efecto del profesor y con l\u00ednea base (pretest-postest). Algunas variables de desarrollo cognitivo y manejo del lenguaje de los ni\u00f1os se medir\u00e1n para realizar controles estad\u00edsticos en el an\u00e1lisis de datos. El incremento en la calidad de las pr\u00e1cticas pedag\u00f3gicas ser\u00e1 determinado mediante el an\u00e1lisis de registros audiovisuales obtenidos durante la intervenci\u00f3n escolar, los cuales ser\u00e1n codificados y analizados acorde a un instrumento bien conocido en la literatura internacional.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> Proyecto Fondecyt de Iniciaci\u00f3n 11201211<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2019 - Octubre 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26745\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Ideolog\u00edas poscoloniales, pol\u00edticas de reconocimiento y reparaci\u00f3n, y relaciones intergrupales actuales: los Mapuche en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26745\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26745\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto fue el mejor evaluado (N.\u00ba 1) en el concurso Fondecyt de Iniciaci\u00f3n del a\u00f1o 2020 en el Grupo de Estudios de Psicolog\u00eda y cuenta con un equipo de ocho ayudantes de investigaci\u00f3n, contando entre sus miembros con dos personas de origen Mapuche. El proyecto cuenta con capacitaciones interculturales y sobre la cultura e identidad Mapuche realizadas por una persona Mapuche con titulo de educadora intercultural (Ana \u00d1anculef) y estamos en constante di\u00e1logo con comunidades Mapuche en la Regi\u00f3n de la Araucan\u00eda y en la Regi\u00f3n Metropolitana. En este proyecto hemos logrado entrevistar a personas hablantes del Mapudungun, y as\u00ed tener un mayor nivel de impacto social en el proyecto. Este proyecto es novedoso en Chile, ya que no se han abordado las ideolog\u00edas postcoloniales de manera sistem\u00e1tica en el pa\u00eds, ni tampoco se han estudiado en relaci\u00f3n con la discusi\u00f3n sobre pol\u00edticas p\u00fablicas de reparaci\u00f3n y reconocimiento del pueblo Mapuche. Este proyecto cuenta adem\u00e1s con la colaboraci\u00f3n del Profesor Chris Sibley, de Nueva Zelanda, un destacado acad\u00e9mico en el \u00e1rea de estudios con pueblos originarios y estudios longitudinales sobre conflicto social. Tenemos prevista una visita de este Profesor a Chile durante 2022.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2019 - Octubre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26770\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Supervised Learning Techniques for Relational Databases\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26770\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26770\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]In general, machine learning aims to learn a model from the input data in order to make reliable and repeatable decisions. The learning of a model is either done automatically or semiautomatically. While deep learning can be used to automatically learn a model from arbitrary raw data, the number of successful application domains is still very restricted.\r\nThis proposal is concerned with supervised learning - a machine-learning technique that aims at learning a model from input-output examples. A crucial task in supervised learning is the engineering of the features. Features are used to extract the relevant information from the raw data in order to learn a classifier that is based on the extracted data. A classifier is a function that partitions the input data into different categories. Feature engineering is a time-consuming process that includes a lot of trial and error, and stepwise addition or deletion of features. We aim at automating that process and learn a classifier based on some automatically generated features.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11190900<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27073\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            REAL TIME CORRELATION BETWEEN THE STRAIN RATE IN STANDARD MECHANICAL TESTS AND MICROSTRUCTURAL CHANGES IN METALS: AN ACOUSTIC POINT OF VIEW\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27073\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27073\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Dislocations are the main source of plastic behavior of metals, however, it is very difficult to quantitatively\r\nstudy their influence. In order to improve this situation, it is proposed to use its interaction with elastic waves\r\nas a non-invasive probe in Aluminum and Steel 304L at different strain-rates. The long-term objective of the\r\nresearch presented in this proposal is to obtain a standardized methodology for the characterization of\r\nmaterials by means of ultrasonic tests.\r\nThe proposed technique is based on in-situ measurements of wave pulse propagation in rectangular samples\r\n(with ASTM Standard) under standard tensile tests, with maximum deformations of the order of 3% to 7%,\r\nwhich includes both the elastic regime and the plastic, additionally considers traction speeds between 0.001\r\nmm \/ s and 0.5 mm \/ s. The results are contrasted with measurements of ultrasonic resonance spectroscopy\r\n(RUS) and density measurements of dislocations by XRD of pieces of the material obtained from the test\r\npieces under traction study, which will be carried out in collaboration with Prof. Claudio Aguilar of the\r\nUniversity Santa Maria. We will also explore a correlation of the results with the microstructural\r\ncharacterization using TEM images\r\nOn the other hand, it is proposed to implement non-linear measures in-situ during tensile tests, which have\r\nbeen shown to be much more sensitive to the presence of dislocations of a material. The non-linear\r\nmeasurements are based on the application of a continuous ultrasonic wave and the analysis is performed\r\non the amplitude of the first harmonic A2&#969; as a function of the amplitude of incident mode A&#969;, those that\r\nare related of the form A2&#969; = &#946;A&#969;, with &#946; a non-linear parameter. For this analysis it is proposed to develop\r\nthe theory, until now non-existent, between the non-linear parameter and the density of dislocations in\r\ncollaboration with Prof. Fernando Lund of the Physics Department of the FCFM of the University of Chile.\r\nEmphasis will then be placed on in situ measurements, where a quantitative and continuous relationship\r\nbetween the density of dislocations and the stress applied during a tensile test has recently been found, as\r\nwell as an indication of universality and independence of the initial condition once that the system enters the\r\nplastic deformation regime.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2019 - Octubre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26424\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Uso de nanoemulsiones de aceites esenciales de Origanum vulgare (or\u00e9gano) y Lavandula dentata (lavanda) como nuevas formulaciones con actividad antif\u00fangica y antitumoral\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26424\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26424\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto FIOUCH 2019 S-19-16[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2019 - Marzo 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26146\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Tagua Tagua Milenaria\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26146\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26146\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Levantar el proyecto Tagua Tagua[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26030\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Programa de desarrollo profesional VER+\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26030\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26030\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Licitado por el CIAE de la Universidad de Chile[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2019 - Noviembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26106\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Apoyo al desarrollo de la Escuela e Instituto de Educaci\u00f3n de la Universidad de O\u0092Higgins para el fortalecimiento de la formaci\u00f3n inicial en los programas de Pedagog\u00eda\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26106\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26106\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2019 - Noviembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26159\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Apoyo al desarrollo de la Escuela e Instituto de Educaci\u00f3n de la Universidad de O\u0092Higgins para el fortalecimiento de la formaci\u00f3n inicial en los programas de Pedagog\u00eda\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26159\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26159\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2019 - Noviembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26200\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Apoyo al desarrollo de la Escuela e Instituto de Educaci\u00f3n de la Universidad de O\u0092Higgins para el fortalecimiento de la formaci\u00f3n inicial en los programas de Pedagog\u00eda\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26200\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26200\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2019 - Abril 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26405\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Influencia del cortisol en la memoria de trabajo en estudiantes de preb\u00e1sica de distintos niveles socioecon\u00f3micos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26405\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26405\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La propuesta tiene como objetivo describir la relaci\u00f3n entre el nivel de estr\u00e9s, medido a trav\u00e9s del nivel de cortisol, con una de las funciones ejecutivas, memoria de trabajo, a trav\u00e9s de distintos niveles socioecon\u00f3micos. Estas interacciones son de inter\u00e9s ya que la capacidad de la memoria de trabajo es predictiva del desempe\u00f1o acad\u00e9mico en contextos educativos formales, y a su vez, hay una relaci\u00f3n entre la capacidad de memoria de trabajo y el nivel socioecon\u00f3mico. Sin embargo, hay evidencia de que no ser\u00eda el nivel socioecon\u00f3mico propiamente tal lo que afecta la capacidad de la memoria de trabajo, sino que el nivel de estr\u00e9s asociado a dicho contexto social. Por tanto, se explorar\u00e1n en las interacciones entre las variables cortisol, capacidad de memoria de trabajo y nivel socioecon\u00f3mico. Esto se har\u00e1 en dos cohortes de estudiantes de\r\npreb\u00e1sica (70 estudiantes de prekinder y 90 de k\u00ednder) de un colegio sin selecci\u00f3n (m\u00e9todo aleatorio), y que por lo tanto tiene estudiantes de distintos niveles socioecon\u00f3micos en los mismos cursos. Es el primer estudio de este tipo realizado en\r\nChile a la fecha, y se espera encontrar evidencia suficiente para dise\u00f1ar programas de intervenci\u00f3n temprana que regulen el nivel de estr\u00e9s en ni\u00f1os con el fin de disminuir los niveles de cortisol, evitando as\u00ed un efecto perjudicial en la memoria de trabajo. Esto, esperando que resulte en un mayor desempe\u00f1o acad\u00e9mico independiente del nivel de estr\u00e9s que pudiese estar asociado a ciertos niveles socioecon\u00f3micos.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2019 - Noviembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26521\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Apoyo al desarrollo de la Escuela e Instituto de Educaci\u00f3n de la Universidad de O\u0092Higgins para el fortalecimiento de la formaci\u00f3n inicial en los programas de Pedagog\u00eda\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26521\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26521\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2019 - Noviembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26713\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Apoyo al desarrollo de la Escuela e Instituto de Educaci\u00f3n de la Universidad de O\u0092Higgins para el fortalecimiento de la formaci\u00f3n inicial en los programas de Pedagog\u00eda\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26713\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26713\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> BIP 40014348-0<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2019 - Enero 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26937\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Piloto de recarga artificial en acu\u00edferos de Elqui\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26937\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26937\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La experiencia internacional (Israel, Holanda, Espa\u00f1a) muestra que la recarga artificial de acu\u00edferos es una herramienta eficaz para lograr gestionar la cantidad y calidad del recurso h\u00eddrico considerando integralmente las fuentes superficiales, subterr\u00e1neas y su interacci\u00f3n. La presente iniciativa tiene como prop\u00f3sito dise\u00f1ar un piloto de Recarga artificial para el acu\u00edfero de Pan de Az\u00facar y Elqui Bajo. Esto significa seleccionar la localizaci\u00f3n \u00f3ptima con criterios hidrogeol\u00f3gicos (capacidad de almacenamiento, niveles piezom\u00e9tricos, velocidad de recarga, transmisibilidad, modelo hidrogeol\u00f3gico de recarga, etc), hidrogeoqu\u00edmicos (calidad del agua, interacci\u00f3n suelo-agua, factores antr\u00f3picos, etc), socio-econ\u00f3micos (salud de la poblaci\u00f3n, productividad, empleo, etc) y ambientales (aspectos ambientales, impactos ambientales).\r\nUna vez seleccionada la localizaci\u00f3n, est\u00e1 ser\u00e1 caracterizada. Para ello se utilizar\u00e1 informaci\u00f3n bibliogr\u00e1fica general y espec\u00edfica disponible.  Parte importante de esta informaci\u00f3n ha sido generada por el equipo UCN que en los \u00faltimos a\u00f1os ha ejecutado proyectos estudiando los acu\u00edferos costeros en la regi\u00f3n.  Tambi\u00e9n se generar\u00e1 informaci\u00f3n complementaria, con campa\u00f1as de caracterizaci\u00f3n y monitoreo, necesaria para la aplicaci\u00f3n de los criterios establecidos. Con la informaci\u00f3n de caracterizaci\u00f3n se determinar\u00e1 la t\u00e9cnica de infiltraci\u00f3n m\u00e1s adecuada a partir de criterios t\u00e9cnicos-cient\u00edficos. Para esto se modelar\u00e1 hidrogeol\u00f3gicamente la efectividad en el corto, mediano y largo plazo de la infiltraci\u00f3n definida. Finalmente, se realizar\u00e1 el dise\u00f1o ingenieril a nivel de detalle de la planta piloto que permita la inyecci\u00f3n artificial el acu\u00edfero.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2019 - Diciembre 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26160\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desarrollo de habilidades de lenguaje y matem\u00e1ticas en ni\u00f1os con diagn\u00f3stico de TEL\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26160\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26160\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Desarrollo de habilidades de lenguaje y matem\u00e1ticas en ni\u00f1os con diagn\u00f3stico de TEL de estudiantes de primer a\u00f1o b\u00e1sico en la regi\u00f3n de O'Higgins[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2019 - Marzo 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26004\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia: D. suzukii mitigaci\u00f3n econ\u00f3mica y social mediante una estrategia de difusi\u00f3n y manejo integrado\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26004\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26004\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El Objetivo del proyecto es mitigar impacto econ\u00f3mico mediante difusi\u00f3n y capacitaciones taxon\u00f3micas y visuales enfocadas a peque\u00f1os productores, logrando un plan de manejo integrado de la plaga.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2019 - Marzo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26092\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Proyecto PAR Explora O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26092\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26092\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2019 - Marzo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26292\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Variational analysis of soft materials\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26292\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26292\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Work on the open problem of proving existence of minimizers in nonlinear elasticity in the paradigmatic neoHookean model.\r\nFinite element simulations, modelling, and experiments for swelling of polymer gels bonded to rigid substrates.\r\nFinite element simulations, modelling, and asymptotic analysis for Schallamach waves in the detachment of thin hydrogels.\r\nProof that the transition, in elastomers and ductile materials, from multiple independent spherical cavitation to the coalescence stage occurs when the size, in the deformed configuration, of the opened cavities is comparable to the distance, in the reference configuration, between the cavitation singularities.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2019 - Marzo 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26347\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia: D. suzukii mitigaci\u00f3n econ\u00f3mica y social mediante una estrategia de difusi\u00f3n y manejo integrado\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26347\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26347\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El Objetivo del proyecto es mitigar impacto econ\u00f3mico mediante difusi\u00f3n y capacitaciones taxon\u00f3micas y visuales enfocadas a peque\u00f1os productores, logrando un plan de manejo integrado de la plaga.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2019 - Marzo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26406\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Proyecto PAR Explora O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26406\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26406\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2019 - Marzo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26435\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Proyecto PAR Explora O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26435\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26435\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2019 - Marzo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26522\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Proyecto PAR Explora O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26522\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26522\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2019 - Octubre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26542\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Evaluaci\u00f3n experimental de la tolerancia asociativa al THC y de los efectos de la administraci\u00f3n de THC durante la gestaci\u00f3n y la lactancia en el aprendizaje y la memoria\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26542\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26542\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El tetrahidrocannabinol (THC) es el principal compuesto activo de la Cannabis, siendo el causante de los\r\nefectos estupefacientes de la droga. Esta droga se considera una de las drogas de abuso m\u00e1s prevalentes\r\nen la poblaci\u00f3n, se estima que casi un 5% de los adultos en el planeta consumen cannabis, con pa\u00edses\r\ncomo Estados Unidos con un consumo de m\u00e1s del 12% de los adultos. En la actualidad el uso recreacional\r\ny medicinal de la cannabis esta en alza y se espera su consumo contin\u00fae aumentando, sobretodo en\r\nj\u00f3venes.\r\nLa primera administraci\u00f3n de THC causa m\u00faltiples efectos en el organismo. Por ejemplo, una dosis de THC\r\npuede causar analgesia, ataxia (descoordinaci\u00f3n motora), inhibici\u00f3n motora, actividad anticonvulsionante,\r\nhipotermia, inmovilidad, incremento en el apetito, euforia seguida de sedaci\u00f3n, dificultades en la memoria,\r\nentre otros efectos. Sin embargo, estos efectos disminuyen tras la administraci\u00f3n cr\u00f3nica por semanas y\r\nmeses de la droga, tanto en estudios con humanos como con animales de laboratorio, demostrando as\u00ed el\r\ndesarrollo de tolerancia a ciertos efectos del THC.\r\nDesde una an\u00e1lisis Pavloviano de la tolerancia a las drogas, los est\u00edmulos, contextos y situaciones\r\npresentes al momento de la administraci\u00f3n de una droga funcionan como est\u00edmulos condicionados, y los\r\nefectos de la droga en el sistema nervioso como est\u00edmulos incondicionados. As\u00ed, cuando los efectos de la\r\nadministraci\u00f3n de una droga perturban la homeostasis del organismo, este responde con respuestas\r\nincondicionadas opuestas que compensan los efectos de la droga, ayudando as\u00ed a restablecer la\r\nhomeostasis. Dado que la evaluaci\u00f3n de la tolerancia a los efectos del THC no ha sido explorada desde esta\r\nperspectiva asociativa, a pesar de ser un modelo que bien explica la tolerancia a otras drogas como la\r\nmorfina y el etanol, en el presente proyecto proponemos evaluar los efectos agudos, la tolerancia, y la\r\nespecificidad contextual de la tolerancia al THC. Adem\u00e1s, considerando la importancia del desarrollo\r\ndurante la gestaci\u00f3n y la lactancia, evaluaremos los efecto de la administraci\u00f3n de THC en estas etapas,\r\ntanto en el desarrollo de tolerancia como en posibles efectos detrimentales en la memoria y el aprendizaje.\r\nConsiderando lo anterior, en el presente proyecto proponemos evaluar los efectos agudos, la tolerancia, y\r\nla especificidad contextual de la tolerancia al THC en ratas Sprague Dawley. As\u00ed, la Serie experimental 1\r\nevaluar\u00e1 los efectos del THC en la coordinaci\u00f3n motora (utilizando una Rueda caminadora), la 2 evaluar\u00e1\r\nlos efectos del THC en la locomoci\u00f3n (utilizando un Campo abierto), y la 3 evaluar\u00e1 los efectos del THC en\r\nla memoria (utilizando una Laberinto radial), todo esto en ratas a cuyas madres se les administr\u00f3 THC\r\ndurante la gestaci\u00f3n y la lactancia y a ratas cuyas madres no han recibido THC. La Serie experimental 4\r\nevaluar\u00e1 el aprendizaje y la memoria en ratas a cuyas madres se les administr\u00f3 THC durante la gestaci\u00f3n y\r\nla lactancia (utilizando un Laberinto radial y cajas de condicionamiento). En espec\u00edfico, los Experimento\r\n1.1, 2.1, y 3.1 eval\u00faan diariamente a los sujetos por 30 d\u00edas en su coordinaci\u00f3n motora, locomoci\u00f3n, y\r\nmemoria, respectivamente, antes y despu\u00e9s de una administraci\u00f3n de THC. Adicionalmente los sujetos\r\nser\u00e1n evaluados de igual forma en el contexto regular de administraci\u00f3n y en un nuevo contexto, para\r\ndeterminar as\u00ed la situacionalidad de la tolerancia. Los Experimentos 1.2, 2.2, y 3.2 siguen los mismos\r\nprocedimientos, pero se realizar\u00e1n en tres grupos de ratas, ratas a cuyas madres de les administr\u00f3 THC\r\ndurante la gestaci\u00f3n y la lactancia y ratas descendientes de madres sin experiencia con el THC. En los\r\nExperimento 4.1, 4.2, y 4.3 tres grupos de ratas ser\u00e1n evaluadas en su capacidad para adquirir una\r\nasociaci\u00f3n Pavloviana, una operante, y en una tare de memoria, respectivamente. Se utilizar\u00e1n ratas a\r\ncuyas madres de les administr\u00f3 THC durante la gestaci\u00f3n y la lactancia y ratas descendientes de madres\r\nsin experiencia con el THC. Se espera que la administraci\u00f3n aguda de THC tendr\u00e1 un efecto detrimental en\r\nla coordinaci\u00f3n motora, la locomoci\u00f3n, y la memoria, que los sujetos desarrollar\u00e1n tolerancia a los efectos\r\ndel THC luego de m\u00faltiples administraciones, y que esta tolerancia ser\u00e1 especifica al contexto de\r\nadministraci\u00f3n. Adem\u00e1s, se espera que la administraci\u00f3n de THC durante la gestaci\u00f3n y el embarazo tenga\r\nun efecto detrimental en la coordinaci\u00f3n motora, la locomoci\u00f3n, y la memoria, que acelere el desarrollo de\r\nla tolerancia sin necesariamente afectar la situacionalidad de la tolerancia. Finalmente, se espera que la\r\nadministraci\u00f3n de THC durante la gestaci\u00f3n y el embarazo tenga un efecto detrimental en el aprendizaje de\r\ntareas de condicionamiento Pavloviano apetitivo, de condicionamiento operante apetitivo, y de memoria.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2019 - Marzo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26637\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Proyecto PAR Explora O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26637\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26637\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2019 - Octubre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26724\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Evaluaci\u00f3n experimental de la tolerancia asociativa al THC y de los efectos de la administraci\u00f3n de THC durante la gestaci\u00f3n y la lactancia en el aprendizaje y la memoria\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26724\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26724\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El tetrahidrocannabinol (THC) es el principal compuesto activo de la Cannabis, siendo el causante de los\r\nefectos estupefacientes de la droga. Esta droga se considera una de las drogas de abuso m\u00e1s prevalentes\r\nen la poblaci\u00f3n, se estima que casi un 5% de los adultos en el planeta consumen cannabis, con pa\u00edses\r\ncomo Estados Unidos con un consumo de m\u00e1s del 12% de los adultos. En la actualidad el uso recreacional\r\ny medicinal de la cannabis esta en alza y se espera su consumo contin\u00fae aumentando, sobretodo en\r\nj\u00f3venes.\r\nLa primera administraci\u00f3n de THC causa m\u00faltiples efectos en el organismo. Por ejemplo, una dosis de THC\r\npuede causar analgesia, ataxia (descoordinaci\u00f3n motora), inhibici\u00f3n motora, actividad anticonvulsionante,\r\nhipotermia, inmovilidad, incremento en el apetito, euforia seguida de sedaci\u00f3n, dificultades en la memoria,\r\nentre otros efectos. Sin embargo, estos efectos disminuyen tras la administraci\u00f3n cr\u00f3nica por semanas y\r\nmeses de la droga, tanto en estudios con humanos como con animales de laboratorio, demostrando as\u00ed el\r\ndesarrollo de tolerancia a ciertos efectos del THC.\r\nDesde una an\u00e1lisis Pavloviano de la tolerancia a las drogas, los est\u00edmulos, contextos y situaciones\r\npresentes al momento de la administraci\u00f3n de una droga funcionan como est\u00edmulos condicionados, y los\r\nefectos de la droga en el sistema nervioso como est\u00edmulos incondicionados. As\u00ed, cuando los efectos de la\r\nadministraci\u00f3n de una droga perturban la homeostasis del organismo, este responde con respuestas\r\nincondicionadas opuestas que compensan los efectos de la droga, ayudando as\u00ed a restablecer la\r\nhomeostasis. Dado que la evaluaci\u00f3n de la tolerancia a los efectos del THC no ha sido explorada desde esta\r\nperspectiva asociativa, a pesar de ser un modelo que bien explica la tolerancia a otras drogas como la\r\nmorfina y el etanol, en el presente proyecto proponemos evaluar los efectos agudos, la tolerancia, y la\r\nespecificidad contextual de la tolerancia al THC. Adem\u00e1s, considerando la importancia del desarrollo\r\ndurante la gestaci\u00f3n y la lactancia, evaluaremos los efecto de la administraci\u00f3n de THC en estas etapas,\r\ntanto en el desarrollo de tolerancia como en posibles efectos detrimentales en la memoria y el aprendizaje.\r\nConsiderando lo anterior, en el presente proyecto proponemos evaluar los efectos agudos, la tolerancia, y\r\nla especificidad contextual de la tolerancia al THC en ratas Sprague Dawley. As\u00ed, la Serie experimental 1\r\nevaluar\u00e1 los efectos del THC en la coordinaci\u00f3n motora (utilizando una Rueda caminadora), la 2 evaluar\u00e1\r\nlos efectos del THC en la locomoci\u00f3n (utilizando un Campo abierto), y la 3 evaluar\u00e1 los efectos del THC en\r\nla memoria (utilizando una Laberinto radial), todo esto en ratas a cuyas madres se les administr\u00f3 THC\r\ndurante la gestaci\u00f3n y la lactancia y a ratas cuyas madres no han recibido THC. La Serie experimental 4\r\nevaluar\u00e1 el aprendizaje y la memoria en ratas a cuyas madres se les administr\u00f3 THC durante la gestaci\u00f3n y\r\nla lactancia (utilizando un Laberinto radial y cajas de condicionamiento). En espec\u00edfico, los Experimento\r\n1.1, 2.1, y 3.1 eval\u00faan diariamente a los sujetos por 30 d\u00edas en su coordinaci\u00f3n motora, locomoci\u00f3n, y\r\nmemoria, respectivamente, antes y despu\u00e9s de una administraci\u00f3n de THC. Adicionalmente los sujetos\r\nser\u00e1n evaluados de igual forma en el contexto regular de administraci\u00f3n y en un nuevo contexto, para\r\ndeterminar as\u00ed la situacionalidad de la tolerancia. Los Experimentos 1.2, 2.2, y 3.2 siguen los mismos\r\nprocedimientos, pero se realizar\u00e1n en tres grupos de ratas, ratas a cuyas madres de les administr\u00f3 THC\r\ndurante la gestaci\u00f3n y la lactancia y ratas descendientes de madres sin experiencia con el THC. En los\r\nExperimento 4.1, 4.2, y 4.3 tres grupos de ratas ser\u00e1n evaluadas en su capacidad para adquirir una\r\nasociaci\u00f3n Pavloviana, una operante, y en una tare de memoria, respectivamente. Se utilizar\u00e1n ratas a\r\ncuyas madres de les administr\u00f3 THC durante la gestaci\u00f3n y la lactancia y ratas descendientes de madres\r\nsin experiencia con el THC. Se espera que la administraci\u00f3n aguda de THC tendr\u00e1 un efecto detrimental en\r\nla coordinaci\u00f3n motora, la locomoci\u00f3n, y la memoria, que los sujetos desarrollar\u00e1n tolerancia a los efectos\r\ndel THC luego de m\u00faltiples administraciones, y que esta tolerancia ser\u00e1 especifica al contexto de\r\nadministraci\u00f3n. Adem\u00e1s, se espera que la administraci\u00f3n de THC durante la gestaci\u00f3n y el embarazo tenga\r\nun efecto detrimental en la coordinaci\u00f3n motora, la locomoci\u00f3n, y la memoria, que acelere el desarrollo de\r\nla tolerancia sin necesariamente afectar la situacionalidad de la tolerancia. Finalmente, se espera que la\r\nadministraci\u00f3n de THC durante la gestaci\u00f3n y el embarazo tenga un efecto detrimental en el aprendizaje de\r\ntareas de condicionamiento Pavloviano apetitivo, de condicionamiento operante apetitivo, y de memoria.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2019 - Marzo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26786\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            La profesionalizaci\u00f3n de la historiograf\u00eda chilena: pol\u00edticas, conceptos y discursos en su articulaci\u00f3n como campo intelectual (1930\u00961990)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26786\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26786\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetivo central  de esta investigaci\u00f3n es analizar la profesionalizaci\u00f3n de la historiograf\u00eda en Chile entre 1930 y 1990 y dar cuenta como se construy\u00f3 un campo disciplinar que interrelacion\u00f3 esferas discursivas, sociopol\u00edticas y conceptuales. La historiograf\u00eda, como campo intelectual, est\u00e1 compuesto por intercambios, debates, publicaciones y formas consensuadas y en disputa de pensar y de escribir hist\u00f3ricamente, en redes locales, nacionales y globales. Como lo han se\u00f1alado recientes estudios de Historia Intelectual, las transformaciones experimentadas por un campo, como en cualquier otra pr\u00e1ctica intelectual, se producen no s\u00f3lo por la agencia de determinadas voces del campo sino que tambi\u00e9n a partir de variables sociales y discursivas que permiten una comprensi\u00f3n din\u00e1mica de la realidad. Dicha complejidad ha sido abordada fragmentadamente en los estudios sobre historiograf\u00eda chilena. En su mayor\u00eda, han sido elaborados sobre una limitada muestra de textos reducidos a las voces predominantes y sin an\u00e1lisis emp\u00edricos que nos permitan identificar longitudinalmente su influencia en la profesionalizaci\u00f3n del campo historiogr\u00e1fico. La hip\u00f3tesis que gu\u00eda esta investigaci\u00f3n sostiene que las categor\u00edas de lenguaje usadas en la historiograf\u00eda son un sistema de significados que media discursivamente entre la esfera sociopol\u00edtica y la agencia de resignificaci\u00f3n que realizan historiadores e historiadoras durante la investigaci\u00f3n y la escritura. A partir de 1930 la profesionalizaci\u00f3n de la historiograf\u00eda chilena y su desarrollo como campo intelectual se produjo en la esfera de las mediaciones discursivas. Espec\u00edficamente, en (1) el desarrollo de nuevas formas de intertextualidad para el tratamiento de fuentes y para el acceso al conocimiento consensuado global-local del campo historiogr\u00e1fico y, en (2) en el desarrollo de numerosos estratos conceptuales y de nuevos recursos discursivos que se diversificaron r\u00e1pidamente en el campo historiogr\u00e1fico El per\u00edodo estudiado va desde los inicios de la profesionalizaci\u00f3n de la historiograf\u00eda en 1930, d\u00e9cada de creaci\u00f3n del primer departamento de historia en Chile, hasta 1990, fecha en que la nueva ley de educaci\u00f3n modific\u00f3 sustancialmente la educaci\u00f3n universitaria y, por ende, la profesionalizaci\u00f3n de la historiograf\u00eda. \r\n\tLos objetivos espec\u00edficos del estudio son: 1) analizar el contexto sociopol\u00edtico que permiti\u00f3 la articulaci\u00f3n de la historiograf\u00eda en Chile y su profesionalizaci\u00f3n entre 1930 y 1990, 2) comprender las transformaciones conceptuales de la historiograf\u00eda chilena entre 1930 y 1990 y 3) caracterizar algunos rasgos discursivos de la historiograf\u00eda chilena entre 1930 y 1990. Se trata de un estudio con un dise\u00f1o metodol\u00f3gico interdisciplinario que utiliza herramientas de la historia conceptual y del an\u00e1lisis del discurso. Las fuentes del estudio la forman 3 conglomerados: 1) fuentes institucionales; 2) trabajos de fin de carrera y 3) referencias historiogr\u00e1ficas de los trabajos de fin de carrera. Para el conglomerado (1) seleccionamos a la Universidad de Chile, la Pontificia Universidad Cat\u00f3lica de Chile, la Pontificia Universidad Cat\u00f3lica de Valpara\u00edso y la Universidad de Concepci\u00f3n porque, por una parte, se trata de las primeras universidades en formar historiadores\/as que se mantienen hasta hoy por lo que se pueden seguir longitudinalmente en el tiempo. Por otra parte, son las universidades que mantienen archivos con la documentaci\u00f3n necesaria para llevar a cabo esta investigaci\u00f3n, es decir, trabajos de fin de carrera e informaci\u00f3n institucional. Para el conglomerado (2) se analizar\u00e1 una muestra de los trabajos de fin de carrera de cada una de las universidades seleccionadas y para el conglomerado (3) se identificar\u00e1n y analizar\u00e1n todas las referencias presentes en la muestra de los trabajos de fin de carrera.\r\nLa novedad historiogr\u00e1fica del proyecto radica en el problema que estudia, as\u00ed como en su metodolog\u00eda basada en el an\u00e1lisis textual y conceptual de los discursos de la producci\u00f3n historiogr\u00e1fica durante su proceso de profesionalizaci\u00f3n. Desde este punto de vista, la metodolog\u00eda es en s\u00ed mismo parte de la hip\u00f3tesis que destaca la acci\u00f3n de la esfera discursiva en la formaci\u00f3n del campo intelectual. La metodolog\u00eda permitir\u00e1 analizar un importante corpus de textos historiogr\u00e1ficos seleccionados a partir de criterios de representatividad conceptual, tem\u00e1tica y regional.\tPor otra parte, el proyecto ser\u00e1 un aporte a la historia intelectual de la historiograf\u00eda basada en el an\u00e1lisis emp\u00edrico y sistem\u00e1tico de un corpus estudiado longitudinalmente. Una novedad radica en el corpus mayoritariamente compuesto por Trabajos de fin de carrera. Estos reflejan excepcionalmente c\u00f3mo fueron las pr\u00e1cticas de formaci\u00f3n socializaci\u00f3n y educaci\u00f3n de la historiograf\u00eda y su relaci\u00f3n con la esfera sociopol\u00edtica e institucional universitaria entre 1930 y 1990. Por \u00faltimo, aportar\u00e1 al desarrollo de la educaci\u00f3n superior en Chile, especialmente a las carreras de Historia de pre y posgrado, y a organismos del Estado (Ministerio de Educaci\u00f3n, Agencia Nacional de Acreditaci\u00f3n) un conocimiento comprensivo sobre desarrollo hist\u00f3rico de la Educaci\u00f3n Superior en Chile.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2019 - Marzo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26787\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Lectura, escritura y desempe\u00f1o acad\u00e9mico en educaci\u00f3n superior: hacia un modelo de experticia letrada\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26787\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26787\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La educaci\u00f3n superior, tanto en Chile como en Latinoam\u00e9rica, ha experimentado un proceso de masificaci\u00f3n e incorporaci\u00f3n de estudiantes pertenecientes a grupos sociales hist\u00f3ricamente excluidos, pero contin\u00faa mostrando inequidades seg\u00fan factores socioecon\u00f3micos y de distribuci\u00f3n de capital cultural, social y semi\u00f3tico. Por este motivo, se han fomentado pol\u00edticas de ingreso equitativo e iniciativas de apoyo y acompa\u00f1amiento de los estudiantes, incluidos programas y cursos de alfabetizaci\u00f3n acad\u00e9mica. Sin embargo, no existen evidencias concluyentes que demuestren el v\u00ednculo entre el dominio de la lectura, la escritura y el desempe\u00f1o acad\u00e9mico.\r\n\r\nEl objetivo de esta investigaci\u00f3n es aportar evidencias emp\u00edricas para comprender la relaci\u00f3n entre lectura, escritura, desempe\u00f1o acad\u00e9mico y perfiles estudiantiles de educaci\u00f3n superior. La investigaci\u00f3n tiene como objetivos espec\u00edficos 1) determinar si existe relaci\u00f3n entre experticia letrada y desempe\u00f1o acad\u00e9mico; 2) identificar los indicadores de experticia letrada que predicen el desempe\u00f1o acad\u00e9mico; 3) determinar c\u00f3mo se distribuye la experticia letrada en los perfiles sociodemogr\u00e1ficos y educativos de educaci\u00f3n superior; y 4) elaborar un prototipo de Protocolo de categorizaci\u00f3n y alerta temprana de necesidades de apoyo para el desempe\u00f1o acad\u00e9mico basado en la experticia letrada.\r\n\r\nSe seguir\u00e1n m\u00e9todos mixtos para recoger y triangular datos de tipo cuantitativo y cualitativo correspondientes a 6 indicadores que conforman el modelo multivariable de experticia letrada: 1) desempe\u00f1o en pruebas estandarizadas (SIMCE lectura; PSU lenguaje; prueba DEMRE escritura); 2) teor\u00edas impl\u00edcitas; 3) autoeficacia; 4) pr\u00e1cticas letradas acad\u00e9micas; 5) pr\u00e1cticas letradas vern\u00e1culas; 6) ense\u00f1anza de la escritura. La muestra se conformar\u00e1 con la cohorte completa de ingreso 2018 (n=931), la cual re\u00fane perfiles estudiantiles diversos de una instituci\u00f3n estatal, medianamente selectiva y regional perteneciente al CRUCH. Los datos cuantitativos se recolectar\u00e1n a partir de pruebas estandarizadas (ya realizadas) y tests con escalas validadas; se relacionar\u00e1n con el desempe\u00f1o acad\u00e9mico, construido como el promedio individual ponderado acumulado a lo largo de 8 semestres, que funcionar\u00e1 como variable dependiente.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1191179<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2019 - Abril 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27074\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            ULTRASOUND AS A PROBE OF PLASTICITY IN STEELS\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27074\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27074\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Dislocations are at the source of plastic behavior of metals and alloys, yet it is very difficult to quantitatively study their behavior. In order to improve this situation, it is proposed to use their interaction with elastic waves as a nonintrusive probe. The long-term aim of the research presented in this proposal is to enable the development of ultrasound technology as a practical non-intrusive tool for the characterization of plastic behavior of materials.\r\nIn recent years, proposers have shown, using Resonant Ultrasound Spectroscopy (RUS), that an increase of dislocation density in aluminum by a factor of 6 leads to a change for the speed of shear waves on the order of 1%, a quantity that can be measured with an accuracy on the order of 0.1%. They have also shown that local measurements of the speed of shear waves in aluminum under standard testing conditions in tension provide a quantitative, accurate, nonintrusive and continuous relation between dislocation density and externally applied stress, and that an increase in dislocation density by a factor of ten in copper and aluminum leads to an increase in the value of the (nonlinear) parameter that characterizes second harmonic generation by 20 to 60%.\r\nThis proposal seeks to go one more step towards a practical implementation of the proposed ultrasonic testing tool for pieces in service. Materials of wide use in industry, 304L steel and TWIP steel, will be used. And in addition to bulk ultrasonic and shear waves, surface Rayleigh waves will be tested, in order to develop techniques that are useful when pieces in service have a geometry that does not lend itself to bulk wave measurement. Both linear (wave propagation velocity and attenuation) and nonlinear (second harmonic generation) acoustics measurements will be performed, using bulk and surface waves, ex situ after mechanical treatment, and in situ under standard testing conditions. In addition, dislocation density will be measured using X-ray diffraction (XRD) , using both the modified Warren-Averbach and Rietveld methods. Additional characterization will be performed using transmission electron microscopy (TEM) and scanning electron microscopy (SEM).\r\nThe expected result of the proposed research is a set of measurements that relate acoustics parameters to dislocation density in 304L and TWIP steels. The specific goal is that these measurements will provide a framework for the development of devices to nondestructively measure the dislocation density of pieces in service.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> CONICYT\/FONDECYT\/1191239<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2019 - Marzo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27121\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            A political geography of sustainable development, 1972-2022: the multi-scalar political construction of a hybrid socio-ecological paradigm\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27121\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27121\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]This research project has as its overarching question, the following: To what extent have political contexts shaped the evolution of sustainable development praxis? Rather than sustainable development being a single, universal paradigm that has been uniform in its conceptual progression, its integration into public policy, and in public and private practice, the argument that will be explored in this project is that sustainable development is a hybrid conceptual form that has been adapted by different institutions and organizations to fit within specific dominant political frameworks. The hypothesis that guides the research is as follows: Sustainable development, from its emergence at the Stockholm Conference in 1972, has been coopted and adapted by different institutions and organizations to specific, dominant political frameworks, and is therefore a hybrid socio-ecological paradigm that exhibits considerable contextual diversity rather than as a singular global narrative.\r\n\r\nSince the Stockholm Declaration of 1972 which set in motion the agendas around sustainable development and subsequent Summits, leading to the current Agenda 2030, there has been a political struggle to define its conceptual underpinnings and the nature of this evolving socio-ecological paradigm. Considerable research has been undertaken on sustainability issues, and the concept has been brought firmly into public policy considerations. However, most of this work is apolitical, in that \u0096 as a normative concept \u0096 it promotes desirable processes and outcomes, but fails to consider the political frameworks in which sustainable development is situated. The proposed research project seeks to repoliticize the debate around the sustainable development paradigm and understand the different geographies of promotion and diffusion that have taken place since 1972, focusing on the political frameworks that have shaped its incorporation. During the period 1972-2022 (to the next Sustainable Development Summit, Rio+30), the international development context has been defined by ideological positions of capitalism, communism, socialism, neoliberalism, neostructuralism, social democracy and populism, which are themselves often hybridized and heterodox. These ideologies are rarely discussed with reference to sustainable development.\r\n\r\nThe proposed research will analyze the evolution of the paradigm as a political construct at three scales: global, regional (Latin America) and Chile. The three principal objectives are to: 1. Analyze the relationship between political theory and frameworks and the evolution of the sustainable development paradigms at different scales; 2. Examine the factors that shape homogeneity and heterogeneity in the integration of the paradigm in different contexts; 3. Explain the ways in which sustainable development has been coopted and adapted by different political positions, and the relevance of this for understanding sustainable development praxis within the context of Agenda 2030. The methodology is mixed, interpretivist and post-structural. It involves three methods: the analysis of sustainable development theory and political theory in order to develop a conceptual framework for examining the nexus of politics and sustainable development; the analysis of the translation of this nexus into public and practice through the revision of secondary materials and \u0091grey\u0092 sources (e.g. policy agendas and related documents, declarations), involving content analysis and discourse analysis; interviews with key informants to understand perceptions of the paradigm and its politicization in Chile. The expected results will contribute to the critical analysis of the paradigm of sustainable development, its strengths and weaknesses in specific contexts, and a more nuanced appreciation of how Agenda 2030 and the Sustainable Development Goals will be pursued over the coming decade, in Chile and Latin America more widely. In terms of its contribution to knowledge, it will complement work in the fields of political geography, political ecology and historical geography.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26018\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desarrollo del pensamiento matem\u00e1tico formal e informal en educaci\u00f3n preescolar: precursores cognitivos y din\u00e1mica temporal de procesamiento\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26018\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26018\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto busca analizar el rol, peso e interacci\u00f3n que pueden tener algunas variables de tipo cognitivo en aquellas competencias o habilidades matem\u00e1ticas fundamentales. Espec\u00edficamente, es de inter\u00e9s determinar si la memoria de trabajo, memoria de corto plazo, memoria viso-espacial y verbal, estimaci\u00f3n y comparaci\u00f3n num\u00e9rica, y la din\u00e1mica temporal del procesamiento num\u00e9rico, a trav\u00e9s del estudio de los movimientos sac\u00e1dicos, se erigen como precursores del desarrollo matem\u00e1tico inicial, y adem\u00e1s, explicar su interacci\u00f3n conjunta o interdependencia a la hora de explicar la variabilidad en la resoluci\u00f3n de tareas asociadas al pensamiento matem\u00e1tico formal e informal en ni\u00f1os y ni\u00f1as de 4 a 6 a\u00f1os. Su correcta identificaci\u00f3n y aporte puede no s\u00f3lo contribuir a diagnosticar de manera oportuna niveles de rezago o de desarrollo deficitario, sino tambi\u00e9n, posibilita respaldar acciones sistem\u00e1ticas en todo el sistema escolar, como tambi\u00e9n medidas de intervenci\u00f3n focalizadas con aquellos estudiantes que presenten condiciones de riesgo futuro o dificultades con el aprendizaje de la matem\u00e1tica.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> IDI 40008879-0<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2019 - Marzo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26407\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia de \u0093innovaci\u00f3n social en el sector tur\u00edstico\u0094: Modelo de inclusi\u00f3n sociolaboral.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26407\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26407\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Implementar nodos de innovaci\u00f3n social para la inserci\u00f3n de j\u00f3venes con discapacidad por trastornos de salud mental severo, para  que puedan contribuir en el aumento de la competitividad y responsabilidad social en  empresas  del  sector tur\u00edstico  de las comunas de Pichilemu, San Fernando, Rancagua, a trav\u00e9s de un enfoque metodol\u00f3gico  de recuperaci\u00f3n  basado en promoci\u00f3n del desarrollo local, colaborativamente con adultos mayores y mujeres con alto nivel de vulnerabilidad social, durante  los 36 meses de la iniciativa.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> IDI 40008879-0<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2019 - Marzo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26436\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia de \u0093innovaci\u00f3n social en el sector tur\u00edstico\u0094: Modelo de inclusi\u00f3n sociolaboral.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26436\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26436\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Implementar nodos de innovaci\u00f3n social para la inserci\u00f3n de j\u00f3venes con discapacidad por trastornos de salud mental severo, para  que puedan contribuir en el aumento de la competitividad y responsabilidad social en  empresas  del  sector tur\u00edstico  de las comunas de Pichilemu, San Fernando, Rancagua, a trav\u00e9s de un enfoque metodol\u00f3gico  de recuperaci\u00f3n  basado en promoci\u00f3n del desarrollo local, colaborativamente con adultos mayores y mujeres con alto nivel de vulnerabilidad social, durante  los 36 meses de la iniciativa.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 3190229<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2019 - Marzo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26650\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Nonsmooth dynamical system involving regular structures\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26650\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26650\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Nonsmooth dynamical system involving regular structures[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> IDI 40008879-0<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2019 - Marzo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26673\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia de \u0093innovaci\u00f3n social en el sector tur\u00edstico\u0094: Modelo de inclusi\u00f3n sociolaboral.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26673\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26673\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Implementar nodos de innovaci\u00f3n social para la inserci\u00f3n de j\u00f3venes con discapacidad por trastornos de salud mental severo, para  que puedan contribuir en el aumento de la competitividad y responsabilidad social en  empresas  del  sector tur\u00edstico  de las comunas de Pichilemu, San Fernando, Rancagua, a trav\u00e9s de un enfoque metodol\u00f3gico  de recuperaci\u00f3n  basado en promoci\u00f3n del desarrollo local, colaborativamente con adultos mayores y mujeres con alto nivel de vulnerabilidad social, durante  los 36 meses de la iniciativa.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> IDI 40008879-0<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2019 - Marzo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26824\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia de \u0093innovaci\u00f3n social en el sector tur\u00edstico\u0094: Modelo de inclusi\u00f3n sociolaboral.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26824\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26824\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Implementar nodos de innovaci\u00f3n social para la inserci\u00f3n de j\u00f3venes con discapacidad por trastornos de salud mental severo, para  que puedan contribuir en el aumento de la competitividad y responsabilidad social en  empresas  del  sector tur\u00edstico  de las comunas de Pichilemu, San Fernando, Rancagua, a trav\u00e9s de un enfoque metodol\u00f3gico  de recuperaci\u00f3n  basado en promoci\u00f3n del desarrollo local, colaborativamente con adultos mayores y mujeres con alto nivel de vulnerabilidad social, durante  los 36 meses de la iniciativa.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1191317<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2019 - Marzo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26910\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26910\" aria-expanded=\"false\" aria-controls=\"collapse-26910\">\n                                            FONDECYT REGULAR N\u00b0: \u0093El rol de la diversidad cultural en la formaci\u00f3n de profesores en las instituciones de educaci\u00f3n superior del norte grande de Chile\u0094.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26910\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26910\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En el sistema educativo del norte de Chile, se observa la presencia de una diversidad cultural significativa, conformada por estudiantes chilenos y de poblaciones originarias (aymaras, quechuas, afrodescendientes, atacame\u00f1os, mapuches, changos y diaguitas), a lo que se suman los hijos e hijas de inmigrantes, principalmente peruanos, bolivianos, colombianos, venezolanos y haitianos.\r\n\r\nEn este escenario, la presente investigaci\u00f3n tiene como objetivo general analizar el componente de diversidad cultural presente en la formaci\u00f3n inicial de estudiantes de pedagog\u00eda en las Instituciones de Educaci\u00f3n Superior (IES) del Norte grande de Chile, a nivel de la pol\u00edtica institucional, el dise\u00f1o curricular, y las creencias personales y profesionales de acad\u00e9micos y futuros profesores de las IES. Esto, con la finalidad de proponer recomendaciones a la pol\u00edtica p\u00fablica que permitan mejorar sustantivamente la formaci\u00f3n de futuros profesores para enfrentar la diversidad cultural.\r\n\r\nLa problem\u00e1tica de estudio se refiere a que el espacio del norte grande de Chile se ha convertido en un nodo neur\u00e1lgico y estrat\u00e9gico de atracci\u00f3n de poblaciones, generando importantes transformaciones en el sistema escolar, donde se ha ido escalando paulatinamente a la presencia de colectivos diversos en la educaci\u00f3n superior. En relaci\u00f3n a esto, la OCDE (2014) indica que los centros educativos deben estar preparados en todos sus componentes para atender la diversidad cultural; lo que demanda paralelamente una adecuada formaci\u00f3n de los futuros profesores en las instituciones de educaci\u00f3n superior.\r\n\r\nEl dise\u00f1o metodol\u00f3gico de la presente propuesta de investigaci\u00f3n, es de car\u00e1cter mixto con an\u00e1lisis de contenido tem\u00e1tico con estrategias multim\u00e9todos de recolecci\u00f3n de informaci\u00f3n, pues si bien se trata principalmente de un estudio exploratorio, contempla la realizaci\u00f3n de un an\u00e1lisis de informaci\u00f3n ministerial e institucional de las casas de estudio mencionadas, junto con la aplicaci\u00f3n de entrevistas semiestructuradas a acad\u00e9micos y profesionales que dirigen la implementaci\u00f3n de la FID. Desde una perspectiva cuantitativa, se aplicar\u00e1n cuestionarios a una muestra de acad\u00e9micos que impartan clases en carreras de pedagog\u00eda y a una muestra de estudiantes en pr\u00e1ctica de pedagog\u00edas. Toda la informaci\u00f3n cualitativa se analizar\u00e1 con el programa Nvivo 12, obteniendo an\u00e1lisis de contenido y discurso a trav\u00e9s de la teor\u00eda fundamentada.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1190874<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2019 - Marzo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27089\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Variabilidad geogr\u00e1fica en el acceso a la atenci\u00f3n hospitalaria en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27089\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27089\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La pregunta de investigaci\u00f3n se centra en la utilizaci\u00f3n de las camas hospitalarias en cada uno de los 29 Servicios de Salud y en las formas como \u00e9sta contribuye a comprender la variabilidad geogr\u00e1fica del acceso a la atenci\u00f3n hospitalaria en Chile, a partir de una perspectiva de utilizaci\u00f3n de servicios que reciba el paciente, del lugar donde se reciba la atenci\u00f3n y del intervalo de tiempo que implique. En otras palabras, \u00bfEsta distribuci\u00f3n de camas se ajusta a la l\u00f3gica multiseguro de nuestro sistema de salud y la distribuci\u00f3n de la poblaci\u00f3n beneficiaria de FONASA y la del sector privado? \u00bfCu\u00e1les son los diagn\u00f3sticos de admisi\u00f3n hospitalaria m\u00e1s comunes dentro de cada Servicio de Salud?; \u00bfEn qu\u00e9 comunas y hospitales se atienden los individuos diagnosticados?; \u00bfQu\u00e9 grupo socioecon\u00f3mico es m\u00e1s permeable ante una patolog\u00eda?\r\nEstas preguntas invitan a conocer el comportamiento de las cifras de egresos hospitalarios, causas de hospitalizaci\u00f3n y variables asociadas (vgr. Sexo, edad, previsi\u00f3n social, comuna de residencia, d\u00edas de estad\u00eda). Para ello, se emplear\u00e1 el Informe Estad\u00edstico de Egreso Hospitalario (Decreto N\u00ba 1671\/2010) cuyo reporte es obligatorio para todos los establecimientos de salud del territorio nacional, independiente de su car\u00e1cter p\u00fablicos o privado.\r\nEs importante subrayar que en estas interrogantes est\u00e1 el leg\u00edtimo inter\u00e9s de conocer si la atenci\u00f3n hospitalaria depende en gran medida de d\u00f3nde se vive dentro del pa\u00eds. Si bien es posible reconocer que existe una inevitable desigualdad en el acceso geogr\u00e1fico a una cama de hospital debido a la localizaci\u00f3n discreta de los hospitales, lo importante ser\u00eda descartar\/confirmar si en Chile tenemos pacientes mejor o peor situados(as) para aprovechar el suministro de camas hospitalarias en base a sus necesidades o preferencias.\r\nAqu\u00ed el cambio en el perfil epidemiol\u00f3gico de los chilenos toma fuerza (ver tabla 3). Con un alza en las enfermedades no transmisibles, es de esperar mayor frecuencia de patolog\u00edas cr\u00f3nicas y hospitalizaciones m\u00e1s largas. El incremento de la prevalencia de enfermedades cardiovasculares, diabetes, enfermedades respiratorias cr\u00f3nicas y c\u00e1ncer contribuyen una importante demandas por servicios hospitalarios (MINSAL 2011). \u00bfEst\u00e1n todos los \u0093lugares\u0094 respondiendo en forma adecuada?[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1180057<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2019 - Enero 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27104\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27104\" aria-expanded=\"false\" aria-controls=\"collapse-27104\">\n                                            Nuevos v\u00ednculos y desaf\u00edos entre lo art\u00edstico y lo pedag\u00f3gico. Abriendo campos hacia una re-conceptualizaci\u00f3n del arte y el rol del-la artista en la sociedad actual\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27104\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27104\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto \u0093Nuevos V\u00ednculos y Desaf\u00edos entre lo Art\u00edstico y lo Pedag\u00f3gico\u0094 tuvo como objetivo general comprender c\u00f3mo los artistas visuales que tambi\u00e9n se desempe\u00f1an como docentes en Chile vinculan su pr\u00e1ctica art\u00edstica con la pedag\u00f3gica y c\u00f3mo estos cruces tienen el potencial de generar nuevas propuestas en la producci\u00f3n art\u00edstica y la educaci\u00f3n en el pa\u00eds. A partir de esta relaci\u00f3n, el proyecto buscaba replantear el rol de los artistas-docentes como algo m\u00e1s que transmisores de conocimiento, estableci\u00e9ndolos como catalizadores de cambios sociales y culturales en sus comunidades.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2019 - Septiembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26216\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia: Coberturas fotoselectivas en kiwi\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26216\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26216\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Actualmente, ante el escenario de cambio clim\u00e1tico la fruticultura chilena enfrenta importantes desaf\u00edos, siendo los m\u00e1s cr\u00edticos la adaptabilidad de las plantas a las nuevas condiciones edafoclim\u00e1ticas y la escasez de mano de obra capacitada (FIA, 2017). Para afrontar el problema, el sector frut\u00edcola ha recurrido a diversas estrategias, entre ellas, la introducci\u00f3n de nuevas variedades con mejor adaptabilidad, bajos requerimientos de horas fr\u00edo, alto valor agregado y mayor productividad, junto con la adopci\u00f3n de nuevas tecnolog\u00edas y la diversificaci\u00f3n de las especies en los huertos, de manera de asegurar la mano de obra durante toda la temporada.\r\nEl kiwi (Actinidia spp.) es uno de los cultivos que se perfila como una atractiva alternativa productiva por su creciente demanda mundial (3 millones ton), donde Chile se caracteriza por ser el tercer exportador (179.833 ton) despu\u00e9s de Italia y Nueva Zelanda (FAO, 2017). Las regiones del Maule y O\u0092Higgins representan cerca del 90% de la superficie nacional (respectivamente 50,8% y 37%), siendo la variedad \u0093Hayward\u0094 (pulpa verde) tradicionalmente la m\u00e1s cultivada. Dadas las condiciones de alta demanda y mejores precios internacionales, en la \u00faltima d\u00e9cada se han introducido nuevas variedades de pulpa amarilla, las cuales presentan mayor rentabilidad en comparaci\u00f3n a 'Hayward\u0092. En particular, la Regi\u00f3n de O\u0092Higgins con 3.376 ha de kiwi en producci\u00f3n (equivalentes a 73.554 ton), se destaca por la mayor superficie de variedades de pulpa amarilla (50,4% del total nacional; 622 ha) (ASOEX, 2017). Sin embargo, estas \u00faltimas son conocidas por su mayor susceptibilidad al cancro bacteriano (Pseudomona syringae pv. actinidiae; Psa) y a eventos clim\u00e1ticos adversos (e.g. heladas y lluvias primaverales), por lo que se requiere adoptar nuevas estrategias de manejo agron\u00f3mico.\r\n\r\nLa experiencia internacional menciona a los sistemas de cobertura como una \u00f3ptima alternativa para contener y disminuir la presencia del cancro bacteriano del kiwi, reducir el riesgo por adversidades clim\u00e1ticas y mejorar la producci\u00f3n de los huertos. Bajo las condiciones regionales, existen experiencias en el uso de sistemas de cobertura en manzano, cerezo y vid, mientras que en kiwi s\u00f3lo se han realizado algunas aproximaciones, lo cual constituye una oportunidad para aumentar la eficiencia productiva y la rentabilidad del sector frut\u00edcola local.\r\nObjetivo general\r\nAumentar la competitividad de los productores de kiwi mediante la generaci\u00f3n de directrices tecnol\u00f3gicas para el uso de sistemas de cobertura foto-selectivas en la Regi\u00f3n de O\u0092Higgins[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 3190048.<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2019 - Marzo 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26234\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Promoviendo una relaci\u00f3n humano-animal positiva en la industria porcina: el rol del aprendizaje social en la percepci\u00f3n positiva del humano en cerdos de recr\u00eda.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26234\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26234\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto Fondecyt Postdoctorado n  Doctora Daniela Luna. \r\n\tInvestigador Patrocinante[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Patrocinante<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2019 - Marzo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26250\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Laboratorio Biominero para la Regi\u00f3n de O\u0092Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26250\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26250\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Fondo de Innovaci\u00f3n para la Competitividad - FIC2018 - 6ta regi\u00f3n. Gobierno Regional. Proyecto titulado: Laboratorio Biominero para la Regi\u00f3n de O\u0092Higgins. Instituci\u00f3n patrocinante: Universidad de O\u0092Higgins. Marzo 2019-Diciembre 2020.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2019 - Abril 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26251\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Non-coding RNA global transcriptional regulatory network in Enterococcus faecalis.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26251\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26251\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2019 - Abril 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26252\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            RCAN1 trisomy and the control of PINK1 levels in the survival of human Down&#8217;s syndrome induced pluripotent stem cells (iPSC) and iPSC-derived cardiomyocytes\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26252\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26252\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2019 - Diciembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26253\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transcriptional Networks for Mitochondrial Dynamics related to Human Cardiomyocyte Dysfunction.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26253\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26253\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2019 - Diciembre 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26345\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Campus Colchagua Sustentable\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26345\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26345\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivos: Promover y desplegar buenas pr\u00e1cticas medioambientales al interior del Campus Colchagua, a trav\u00e9s de estrategias y acciones que contribuyan al desarrollo sustentable de la comunidad.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2019 - Septiembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26346\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia: Coberturas fotoselectivas en kiwi\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26346\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26346\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Actualmente, ante el escenario de cambio clim\u00e1tico la fruticultura chilena enfrenta importantes desaf\u00edos, siendo los m\u00e1s cr\u00edticos la adaptabilidad de las plantas a las nuevas condiciones edafoclim\u00e1ticas y la escasez de mano de obra capacitada (FIA, 2017). Para afrontar el problema, el sector frut\u00edcola ha recurrido a diversas estrategias, entre ellas, la introducci\u00f3n de nuevas variedades con mejor adaptabilidad, bajos requerimientos de horas fr\u00edo, alto valor agregado y mayor productividad, junto con la adopci\u00f3n de nuevas tecnolog\u00edas y la diversificaci\u00f3n de las especies en los huertos, de manera de asegurar la mano de obra durante toda la temporada.\r\nEl kiwi (Actinidia spp.) es uno de los cultivos que se perfila como una atractiva alternativa productiva por su creciente demanda mundial (3 millones ton), donde Chile se caracteriza por ser el tercer exportador (179.833 ton) despu\u00e9s de Italia y Nueva Zelanda (FAO, 2017). Las regiones del Maule y O\u0092Higgins representan cerca del 90% de la superficie nacional (respectivamente 50,8% y 37%), siendo la variedad \u0093Hayward\u0094 (pulpa verde) tradicionalmente la m\u00e1s cultivada. Dadas las condiciones de alta demanda y mejores precios internacionales, en la \u00faltima d\u00e9cada se han introducido nuevas variedades de pulpa amarilla, las cuales presentan mayor rentabilidad en comparaci\u00f3n a 'Hayward\u0092. En particular, la Regi\u00f3n de O\u0092Higgins con 3.376 ha de kiwi en producci\u00f3n (equivalentes a 73.554 ton), se destaca por la mayor superficie de variedades de pulpa amarilla (50,4% del total nacional; 622 ha) (ASOEX, 2017). Sin embargo, estas \u00faltimas son conocidas por su mayor susceptibilidad al cancro bacteriano (Pseudomona syringae pv. actinidiae; Psa) y a eventos clim\u00e1ticos adversos (e.g. heladas y lluvias primaverales), por lo que se requiere adoptar nuevas estrategias de manejo agron\u00f3mico.\r\n\r\nLa experiencia internacional menciona a los sistemas de cobertura como una \u00f3ptima alternativa para contener y disminuir la presencia del cancro bacteriano del kiwi, reducir el riesgo por adversidades clim\u00e1ticas y mejorar la producci\u00f3n de los huertos. Bajo las condiciones regionales, existen experiencias en el uso de sistemas de cobertura en manzano, cerezo y vid, mientras que en kiwi s\u00f3lo se han realizado algunas aproximaciones, lo cual constituye una oportunidad para aumentar la eficiencia productiva y la rentabilidad del sector frut\u00edcola local.\r\nObjetivo general\r\nAumentar la competitividad de los productores de kiwi mediante la generaci\u00f3n de directrices tecnol\u00f3gicas para el uso de sistemas de cobertura foto-selectivas en la Regi\u00f3n de O\u0092Higgins[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2019 - Septiembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26638\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transferencia: Coberturas fotoselectivas en kiwi\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26638\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26638\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Actualmente, ante el escenario de cambio clim\u00e1tico la fruticultura chilena enfrenta importantes desaf\u00edos, siendo los m\u00e1s cr\u00edticos la adaptabilidad de las plantas a las nuevas condiciones edafoclim\u00e1ticas y la escasez de mano de obra capacitada (FIA, 2017). Para afrontar el problema, el sector frut\u00edcola ha recurrido a diversas estrategias, entre ellas, la introducci\u00f3n de nuevas variedades con mejor adaptabilidad, bajos requerimientos de horas fr\u00edo, alto valor agregado y mayor productividad, junto con la adopci\u00f3n de nuevas tecnolog\u00edas y la diversificaci\u00f3n de las especies en los huertos, de manera de asegurar la mano de obra durante toda la temporada.\r\nEl kiwi (Actinidia spp.) es uno de los cultivos que se perfila como una atractiva alternativa productiva por su creciente demanda mundial (3 millones ton), donde Chile se caracteriza por ser el tercer exportador (179.833 ton) despu\u00e9s de Italia y Nueva Zelanda (FAO, 2017). Las regiones del Maule y O\u0092Higgins representan cerca del 90% de la superficie nacional (respectivamente 50,8% y 37%), siendo la variedad \u0093Hayward\u0094 (pulpa verde) tradicionalmente la m\u00e1s cultivada. Dadas las condiciones de alta demanda y mejores precios internacionales, en la \u00faltima d\u00e9cada se han introducido nuevas variedades de pulpa amarilla, las cuales presentan mayor rentabilidad en comparaci\u00f3n a 'Hayward\u0092. En particular, la Regi\u00f3n de O\u0092Higgins con 3.376 ha de kiwi en producci\u00f3n (equivalentes a 73.554 ton), se destaca por la mayor superficie de variedades de pulpa amarilla (50,4% del total nacional; 622 ha) (ASOEX, 2017). Sin embargo, estas \u00faltimas son conocidas por su mayor susceptibilidad al cancro bacteriano (Pseudomona syringae pv. actinidiae; Psa) y a eventos clim\u00e1ticos adversos (e.g. heladas y lluvias primaverales), por lo que se requiere adoptar nuevas estrategias de manejo agron\u00f3mico.\r\n\r\nLa experiencia internacional menciona a los sistemas de cobertura como una \u00f3ptima alternativa para contener y disminuir la presencia del cancro bacteriano del kiwi, reducir el riesgo por adversidades clim\u00e1ticas y mejorar la producci\u00f3n de los huertos. Bajo las condiciones regionales, existen experiencias en el uso de sistemas de cobertura en manzano, cerezo y vid, mientras que en kiwi s\u00f3lo se han realizado algunas aproximaciones, lo cual constituye una oportunidad para aumentar la eficiencia productiva y la rentabilidad del sector frut\u00edcola local.\r\nObjetivo general\r\nAumentar la competitividad de los productores de kiwi mediante la generaci\u00f3n de directrices tecnol\u00f3gicas para el uso de sistemas de cobertura foto-selectivas en la Regi\u00f3n de O\u0092Higgins[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2019 - Agosto 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26714\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Elaboraci\u00f3n de cuaderno de Ingl\u00e9s Escrito I como base fundamental en el proceso de ense\u00f1anza-aprendizaje para el desarrollo de la producci\u00f3n escrita en estudiantes de Pedagog\u00eda en ingl\u00e9s.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26714\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26714\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FONDECYT 3190055<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2019 - Marzo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26964\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Metabolic profiling of \u0093Black spot disorder\u0094 in stored Hass avocado (Persea america Mill) fruit\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26964\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26964\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Chile is one of the world\u0092s largest producers of avocados contributing to its economy growth. Increased production and international competition, in addition to changes in production conditions, require Chilean producers to focus on developing competitive advantages. Recently, a new problem for Chilean Hass exported avocado has appeared and it is known as \u0093black spot\u0094, which caused rejections of up to 20%. The causes of this disorder are still unknown and sometimes associated to physiological or pathological disorders.  The symptoms visible after storage are variable and the causes of the black spot symptoms are not known in the literature and there is no  scientific consensus regarding the causesof black spot disorder in avocado.\r\nPreliminary work of our group at PUCV has analyzed fruit from orchards from different agro-ecological regions during the season 2017\/2018 and recorded different incidence of black spot associated to climatological conditions and to the defense mechanisms of the fruit. A deep study for better understanding the causal factors of black spot is needed. \r\n\r\nIn this project we hypothesized that black spot development in Hass avocado epidermis is driven by an imbalance of oxidative stress markers and antioxidant defense system. Thus, the main objectives of this proposal are to evaluate the balance\/imbalance between oxidative stress markers and antioxidant defense systems of Hass avocado epidermis at different levels (enzymatic, transcriptomic and metabolomic) and its correlation to \u0093black spot\u0094 development under different scenarios. \r\n\r\nWe will use a metabolomics approach (GC-MS, HPLC and transcriptomics) to monitor changes in antioxidant defense system, reactive oxygen species and fruit quality parameters of stored Hass avocado combined with chemometrics for data integration. Fruits from 2 different orchards (high and no incidence of black spot based on historical data) during two subsequent harvests and two different seasons (early and late season) will be collected and stored in two different storage conditions for subsequent laboratory analyses.\r\n\r\nThe results of this study are expected not only to provide more foundation into the biochemical processes associated to black spot of \u0091Hass\u0092 avocados but also provide potential \u0091biomarkers\u0092 involved in this disorder, which may help to implement postharvest protocols to reduce this problem in practice. Important variables or biomarkers found will be also used in model building to predict black spot development during storage. This project will generate scientific and academic publications, extension and training of young researchers and will strengthen the network with our national and international key partners. The findings of this project will help growers, agronomists, and packing houses achieve significant cost savings during postharvest handling and storage of avocados.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> RTI2018-101351-B-I00<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2019 - Diciembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de Barcelona<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27108\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27108\" aria-expanded=\"false\" aria-controls=\"collapse-27108\">\n                                            Colaboradora Internacional Investigaci\u00f3n I+D \u0093Horizontes culturales de la relaci\u00f3n materna libre. Arte, literatura, legislaci\u00f3n y pensamiento (Siglos XVII-XXI)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27108\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27108\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto busca problematizar la relaci\u00f3n materna libre, a lo largo de los siglos XVII al XXI, ha sido un tema abordado desde diversas perspectivas culturales, incluyendo el arte, la literatura, la legislaci\u00f3n y el pensamiento. Se manifiesta en representaciones art\u00edsticas que muestran la maternidad desde una \u00f3ptica no tradicional, en obras literarias que exploran la complejidad de los lazos materno-filiales, en la evoluci\u00f3n de la legislaci\u00f3n que reconoce diversos tipos de familias y en el pensamiento que cuestiona los roles de g\u00e9nero y la maternidad obligatoria.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 477694<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2019 - Diciembre 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>FONDART<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27109\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27109\" aria-expanded=\"false\" aria-controls=\"collapse-27109\">\n                                            FONDART Regional \u0093Retra-relatos de un parto olvidado. Trabajo de creaci\u00f3n art\u00edstico con madres de la regi\u00f3n de Los Lagos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27109\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27109\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Artista Responsable, FONDART Regional 477694, \u0093Retra-relatos de un parto olvidado. Trabajo de creaci\u00f3n art\u00edstico con madres de la regi\u00f3n de Los Lagos\u0094, marzo a diciembre 2019. Monto: $ 5.896.520[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2019 - Diciembre 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Fondo del Libro y Lectura<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27110\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27110\" aria-expanded=\"false\" aria-controls=\"collapse-27110\">\n                                            Fondo del Libro y Lectura \u0093Experiencias del saber pedag\u00f3gico de mujeres artistas- docentes. Narraciones biogr\u00e1ficas sobre el desplazamiento del saber\u0094.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27110\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27110\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Autora Responsable, Fondo del Libro y Lectura. Apoyo a ediciones. Libro \u00fanico. Ministerio de las Culturas, las Artes y el Patrimonio. T\u00edtulo \u0093Experiencias del saber pedag\u00f3gico de mujeres artistas- docentes. Narraciones biogr\u00e1ficas sobre el desplazamiento del saber\u0094. Editorial Cuarto Propio, marzo a diciembre de 2019. Monto: 6.000.000. \r\n Esta investigaci\u00f3n es sobre el saber docente de cuatro mujeres artistas-docentes en Chile.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 3190824<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Febrero 2019 - Marzo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26616\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Corrosion of stainless steel in extreme conditions: structural evolution of scales in exposure to flow of molten salt\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26616\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26616\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]-[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Febrero 2019 - Diciembre 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26671\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Occupational and environmental toxicology assessment for epidemiological studies in developing countries\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26671\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26671\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The purpose of the workshop was to strength research skills through the exchange of knowledge in Occupational and environmental toxicology in the scientific community. It will help us to identify and reduce physical, chemical and psychosocial risk factors at work and to preserve the health and well-being of workers.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Febrero 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26672\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Proyecto Piloto Cursos Rurales de Salud Ocupacional para Latinoam\u00e9rica\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26672\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26672\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Our aim is to develop an occupational health training program, focusing on professionals and technicians working in rural areas of Latin America, students of health careers conducting their rural internship and related teachers of collaborating universities. The program will be piloted at three sites 2018. The sites were selected to cover a range of typical rural occupational activities and to cover different cultural characteristics (indigenous population, migrant seasonal workers). Each course will be evaluated (e.g., change in knowledge, attitude, and behavior).[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Febrero 2019 - Diciembre 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26674\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Understanding AIDS worldwide studying immunopathogenesis and correlates of protection in HIV infection caused by different subtypes.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26674\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26674\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Through this study, we aimed at establishing an international network to facilitate and initiate the collection of epidemiological and biological evidences aimed at comprehensively assessing the premature aging in children and adolescents infected by HIV, by studying the different phenomena that characterize this status, with particular regards toward CVD, immunosenescence and immunometabolism.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2019 - Marzo 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26118\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Or\u00edgenes epigen\u00e9ticos de la disfunci\u00f3n vascular en el adulto\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26118\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26118\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En la actualidad existe evidencia convincente del limitado impacto que tienen las estrategias destinadas a la prevenci\u00f3n y tratamiento de la hipertensi\u00f3n y otras enfermedades cardiovasculares, una vez que \u00e9stas se manifiestan en el adulto. En este sentido, la identificaci\u00f3n de los mecanismos que determinan a lo largo de la vida, especialmente en etapas tempranas del desarrollo, una mayor susceptibilidad a la aparici\u00f3n de estas enfermedades, representan un desaf\u00edo para implementar estrategias efectivas de prevenci\u00f3n o, alternativas terap\u00e9uticas adecuadas al grado de compromiso de la salud. Considerando la gran influencia que muestra la trayectoria de crecimiento y el estilo de vida sobre el desarrollo de enfermedades vasculares e hipertensi\u00f3n, en los \u00faltimos a\u00f1os ha existido un creciente inter\u00e9s en definir la participaci\u00f3n de mecanismos que modifican la expresi\u00f3n de genes sin alterar la secuencia de estos (i.e. mecanismos epigen\u00e9ticos) sobre el origen y progreso de \u00e9stas. El presente cap\u00edtulo abordar\u00e1 qu\u00e9 es la epigen\u00e9tica, los mecanismos que median dichos efectos y el rol que cumple en definir a nivel molecular la programaci\u00f3n de la(s) respuestas fisiol\u00f3gicas que condicionan el riesgo de desarrollar obesidad en las diferentes etapas del ciclo vital.\r\nLa visi\u00f3n de los factores gen\u00e9ticos como causa de las enfermedades cr\u00f3nicas, incluyendo las cardiovasculares, ha sido el motor de la investigaci\u00f3n biom\u00e9dica en el \u00faltimo siglo. Sin embargo, el padre de la biolog\u00eda moderna, Charles Darwin, plante\u00f3 fuertemente en su obra \u0093El origen de las Especies mediante la Selecci\u00f3n Natural\u0094 que la \u0093ley superior\u0094 del origen de las especies es la adaptaci\u00f3n a \u0093las condiciones de existencia\u0094 (i.e. medioambiente, estilo de vida), la que estar\u00eda por sobre la \u0093selecci\u00f3n natural\u0094 de caracter\u00edsticas heredables (i.e. genes). Posteriormente, ser\u00eda Conrad Waddington en sus estudios de embriolog\u00eda quien propone la importancia de la interacci\u00f3n entre los genes y el ambiente. Lo que se manifiesta en la capacidad que tiene el organismo de generar, a partir un conjunto de genes (genoma) \u00fanico, los distintos tipos y funciones celulares que lo constituyen, mediante respuestas a est\u00edmulos que se suceden en un tiempo y lugar espec\u00edfico. Dicha propiedad del medioambiente de moldear el fenotipo fue definida por Waddington como \u0093epigen\u00e9tica\u0094. \r\nActualmente se denomina como epigen\u00e9tica al conjunto de \u0093mecanismos modificadores del DNA que regulan la plasticidad fenot\u00edpica de una c\u00e9lula u organismo\u0094. A trav\u00e9s de estos mecanismos, nuestros genes pueden expresarse de manera adecuada en respuesta a cambios en el ambiente; pero a la vez definen respuestas fisiol\u00f3gicas a mediano y largo plazo basados en estas se\u00f1ales entregadas por el ambiente. En este contexto, el establecimiento de dichas respuestas limitar\u00eda, a trav\u00e9s del ciclo vital, la plasticidad fenot\u00edpica del individuo. La presente l\u00ednea de investigaci\u00f3n se ha propuesto estudiar los cambios estructurales del sistema vascular y la activaci\u00f3n de mecanismos epigen\u00e9ticos desde etapas tempranas de la vida, que contribuir\u00edan al desarrollo de enfermedades cardiovasculares en el adulto. En este sentido plantemos que \u0093el desarrollo de hipertensi\u00f3n y enfermedades cardiovasculares en el adulto resultar\u00eda de un programaci\u00f3n estructural y epigen\u00e9tica a nivel vascular, mediada por niveles deficitarios de ox\u00edgeno (i.e. hipoxia) y el estr\u00e9s oxidativo intrauterino\u0094. Esta programaci\u00f3n fetal establecer\u00eda una fisiolog\u00eda vascular pro-hipertensiva que devendr\u00eda posteriormente en una disfunci\u00f3n cardiovascular a medida que el individuo envejece.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2019 - Octubre 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26785\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Competencias profesionales en lectura, escritura y oralidad en perfiles de egreso del sistema de educaci\u00f3n superior chileno\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26785\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26785\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En las \u00faltimas d\u00e9cadas se ha producido un proceso global de innovaci\u00f3n curricular con foco en las competencias para el siglo XXI, es decir, las formas de aprender, razonar y participar que permiten comprender, adecuarse y cumplir prop\u00f3sitos en situaciones nuevas y cambiantes. Entre estas competencias se destacan la lectura, la escritura y la oralidad, formas situadas, transferibles y epist\u00e9micas fundamentales para desenvolverse en los roles comunicativos complejos, especializados y din\u00e1micos de la actual sociedad del conocimiento. Sin embargo, investigaciones previas se\u00f1alan que la comunicaci\u00f3n oral y escrita forma parte del curr\u00edculum oculto en instituciones de educaci\u00f3n superior, es decir, no se incluye en planes de estudios, perfiles de egreso, modelos educativos o competencias focalizadas institucionalmente. Por este motivo, es necesario preguntarse cu\u00e1l es el v\u00ednculo entre los procesos recientes de innovaci\u00f3n curricular por competencias y de acreditaci\u00f3n institucional en el sistema de educaci\u00f3n superior, y la presencia de la comunicaci\u00f3n escrita y oral en las competencias profesionales de egreso de las universidades, materializadas institucionalmente en los perfiles de egreso, las competencias \u0093sello\u0094 y los modelos educativos de las diferentes clases de instituciones del sistema.\r\n\r\nEsta investigaci\u00f3n busca identificar la presencia y la naturaleza de la concepci\u00f3n de la lectura, la escritura y la oralidad en los perfiles de egreso de 5 carreras en 10 universidades chilenas diversas, as\u00ed como su grado de consistencia con las competencias y los modelos educativos institucionales.\r\n\r\nLos resultados muestran que la lectura, la escritura y la oralidad aparecen invisibilizadas o con baja frecuencia, y con una visi\u00f3n reproductiva y generalista, en los perfiles de egreso universitarios chilenos. A partir de estos hallazgos, se sugiere que los procesos de innovaci\u00f3n por competencias y acreditaci\u00f3n de carreras e instituciones est\u00e9n informados por una concepci\u00f3n contempor\u00e1nea de la lectura, la escritura y la oralidad como competencias complejas, ret\u00f3ricas, epist\u00e9micas y disciplinarmente situadas, que requieren un lugar expl\u00edcito y un compromiso institucional en la formaci\u00f3n de profesionales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2019 - Diciembre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Superintendencia de Seguridad Social (Concursos SUSESO)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26837\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            La salud mental como factor de riesgo para los accidentes del trabajo y el ausentismo laboral: un estudio de cohorte (Fase 2)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26837\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26837\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Los problemas de salud mental son frecuentes en la poblaci\u00f3n adulta, as\u00ed como en los trabajadores. Las condiciones que generan estr\u00e9s en el ambiente laboral se pueden manifestar como un problema de salud mental entre los trabajadores, y a su vez esto se relaciona con una mayor probabilidad de accidentes y ausentismo laboral. Si se pudiera contar con modelos predictivos que incluyan diferentes variables (del ambiente laboral, sociales, personales, etc.) se podr\u00edan dise\u00f1ar herramientas para la detecci\u00f3n temprana de personas y\/o situaciones con mayor riesgo de accidentabilidad, de igual forma que estrategias de prevenci\u00f3n m\u00e1s efectivas. Para obtener esto se requiere un estudio de cohorte.\r\nEste proyecto corresponde a la segunda etapa de un estudio de cohorte en trabajadores, donde se realizar\u00eda el seguimiento y las evaluaciones del 2do y 3er a\u00f1o. La fase previa tuvo por objetivo la instalaci\u00f3n de la cohorte y la medici\u00f3n de la l\u00ednea basal, que hasta ahora se realiza sin dificultades, en una muestra de alrededor de 390 trabajadores de la Divisi\u00f3n Andina de CODELCO Chile. Esta segunda fase tendr\u00eda como producto un primer modelo predictivo para el riesgo de accidentabilidad y ausentismo laboral.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> DG ECHO H2020 (Ref: 826292 - EVE)<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2019 - Diciembre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>European Commission<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26856\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26856\" aria-expanded=\"false\" aria-controls=\"collapse-26856\">\n                                            EVE: European Volcano Early Warning System\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26856\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26856\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The EVE project aims at facilitating the interaction and cooperation between scientists and Civil Protection Agencies (CPs) to timely anticipate to volcanic disasters. Built upon the previous EC ECHO funded project VeTOOLS, the aim of EVE is to combine the knowledge on the past eruptive behaviour of the volcanoes with the analysis of real time monitoring in order to construct the European volcano EWS.\r\n\r\nEVE will offer an easy and rapid way to forecast in real time how, when and where a new eruption may occur, thus allowing to predict the most probable eruption scenarios and their potential impacts.\r\n\r\nEVE will facilitate scientific and technical cooperation at regional and international scales by defining common actions and protocols to forecast volcanic scenarios and their potential impacts, in real time during a volcanic crisis.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2018 - Junio 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Corporaci\u00f3n de Fomento de la Producci\u00f3n - CORFO<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26006\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Plataforma colaborativa para la gesti\u00f3n de vigilancia, pron\u00f3stico, investigaci\u00f3n y control de la plaga Dros\u00f3fila de alas manchadas, Drosophila suzukii, en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26006\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26006\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto de car\u00e1cter nacional busca entregar un espacio en la red donde se pueda encontrar las herramientas necesarias para realizar vigilancia, pron\u00f3stico, investigaci\u00f3n y control de la plaga emergente Drosophila suzukii. Busca articular informaci\u00f3n t\u00e9cnica, proyectos, art\u00edculos de investigaci\u00f3n e investigadores. Adem\u00e1s entrega informaci\u00f3n en tiempo real a los beneficiarios, productores, investigadores, asesores, sobre las detecciones validadas a nivel comunal.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2018 - Diciembre 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26093\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            IEEE RAS International Summer School on Deep Learning for Robot Vision\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26093\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26093\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2018 - Junio 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Corporaci\u00f3n de Fomento de la Producci\u00f3n - CORFO<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26094\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Plataforma colaborativa para la gesti\u00f3n de vigilancia, pron\u00f3stico, investigaci\u00f3n y control de la plaga Dros\u00f3fila de alas manchadas, Drosophila suzukii, en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26094\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26094\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto de car\u00e1cter nacional busca entregar un espacio en la red donde se pueda encontrar las herramientas necesarias para realizar vigilancia, pron\u00f3stico, investigaci\u00f3n y control de la plaga emergente Drosophila suzukii. Busca articular informaci\u00f3n t\u00e9cnica, proyectos, art\u00edculos de investigaci\u00f3n e investigadores. Adem\u00e1s entrega informaci\u00f3n en tiempo real a los beneficiarios, productores, investigadores, asesores, sobre las detecciones validadas a nivel comunal.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2018 - Junio 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Corporaci\u00f3n de Fomento de la Producci\u00f3n - CORFO<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26217\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Plataforma colaborativa para la gesti\u00f3n de vigilancia, pron\u00f3stico, investigaci\u00f3n y control de la plaga Dros\u00f3fila de alas manchadas, Drosophila suzukii, en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26217\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26217\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto de car\u00e1cter nacional busca entregar un espacio en la red donde se pueda encontrar las herramientas necesarias para realizar vigilancia, pron\u00f3stico, investigaci\u00f3n y control de la plaga emergente Drosophila suzukii. Busca articular informaci\u00f3n t\u00e9cnica, proyectos, art\u00edculos de investigaci\u00f3n e investigadores. Adem\u00e1s entrega informaci\u00f3n en tiempo real a los beneficiarios, productores, investigadores, asesores, sobre las detecciones validadas a nivel comunal.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2018 - Junio 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26471\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desarrollo de un Modelo de Inteligencia Artificial para la Optimizaci\u00f3n del Rendimiento de Bater\u00edas Ion-Litio en Veh\u00edculos El\u00e9ctricos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26471\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26471\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto busca desarrollar un sistema de control de ruta que optimice costos de operaci\u00f3n, minimizando el impacto econ\u00f3mico de la degradaci\u00f3n de bater\u00edas de ion-litio en una flota de veh\u00edculos el\u00e9ctricos.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26041\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Traducci\u00f3n del libro\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26041\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26041\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto tiene por objetivo la traducci\u00f3n al espa\u00f1ol de la obra \"Jouer\/Apprendre\", del fil\u00f3sofo y profesor franc\u00e9s Gilles Broug\u00e8re, y su publicaci\u00f3n por parte de la editorial LOM Ediciones.\r\n\r\nLa obra a traducir pertenece a un autor especializado en temas de sociolog\u00eda de la infancia y cultura l\u00fadica infantil, y especialmente en la relaci\u00f3n entre juego, aprendizaje y educaci\u00f3n desde una perspectiva antropol\u00f3gica y sociol\u00f3gica. Una versi\u00f3n en espa\u00f1ol del libro constituir\u00eda un notable aporte en particular en el \u00e1mbito de la educaci\u00f3n inicial o parvularia, de creciente inter\u00e9s y relevancia en el pa\u00eds, y cruzada por debates y tensiones referentes a la presencia y modalidad de juego a desarrollar en este nivel. Un aspecto a destacar constituye la posible utilizaci\u00f3n del libro para la formaci\u00f3n de educadoras\/es y como apoyo te\u00f3rico para el desarrollo de investigaci\u00f3n en la materia. De manera m\u00e1s amplia, el libro ofrece una visi\u00f3n original en cuanto a su aproximaci\u00f3n te\u00f3rica al juego, como actividad cultural no privativa de la infancia, y m\u00e1s all\u00e1 de las versiones dominantes provenientes de la psicolog\u00eda.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2018 - Octubre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26179\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Understanding the effect of fires on non-mutualistic diazotrophic population structure in mediterranean native forest soils: towards ecosystem services and natural resilience restoration\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26179\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26179\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Fires have historically played an important role in the composition and distribution of terrestrial ecosystems. However, these events have also represented an important pressure that have induced land degradation worldwide; especially in regions with Mediterranean climates with dry summers and elevated temperatures. In forests, fires not only exert an individual effect on each of their components; including vegetation, animals and other natural resources such as soil and water, among others, but also on the relationship among these constituents, which in turns, compromise the functionally of the whole ecosystem. Forest fires directly affect aboveground biomass production and other ecosystem services (i.e. benefits society directly or indirectly obtain from ecosystems). Land burning can also compromise belowground conditions that are essential to support aboveground life. Though soil biological processes are recognized as main drivers of ecosystem recovery following fires, the consequences of land burning on soil microorganisms are less understood than those on soil physicochemical properties. The present research aims precisely to elucidate what are the effects of fires on a particular group of soil microorganisms, crucial for maintenance of proper soil ecosystem services and natural resilience. The microbial specialist studied in this project would be microorganisms capable of nitrogen fixation (diazotrophs), particularly those living in non-mutualistic associations in soil environments (within the soil rhizosphere or as free-living organisms in bulk soils). It is\r\nknown that land burning can negatively impact soil microorganisms directly by compromising diversity and altering their composition; moreover, these pressures can also indirectly affect soil microbiota by altering soil physicochemical properties. Recently, advanced on molecular biology and analytical techniques have allowed to incorporate the study of microbial interactions and adaptations following soil disturbances. Microbial co-occurrences network studies have shed lights on particular microbial taxa relationships (negative\r\nand positive) and adaptations to changes in soil abiotic factors following disturbances. Thus, these analyses can contribute to better understand the ecological significance of environmental pressures on proper soil ecosystem functioning considering the previous background, the present study aims to assess through ecological molecular analyses how non-mutualistic diazotrophic microorganisms interact with other members of the bacterial community and adapt to changes in soil physicochemical conditions in Mediterranean forest following fires. In the present work, it is hypothesized that ecological networks will reveal shifts in non-mutualistic diazotrophic population structure in Mediterranean forest after fires, due to changes in their interactions with other microorganisms\r\nand responses to modified physicochemical properties. To test this hypothesis, classical soil physicochemical analyses and cutting-edge, molecular based, microbial ecology analyses will be implemented in burned and unburned soils of two Mediterranean native forest in the Region of O\u0092Higgins in central Chile. The strategy used for this study will consist of two types of studies: 1)\r\nat the field scale, and 2) at a field-laboratory scale. The field scale study will include burned areas and unburned areas for comparison. The field-laboratory scale experiment will consist of soil samples taken in the field, burned in the laboratory, and incubated at their original site for different periods of time. By accomplishing the proposed project, it is expected to identify what are the main biotic conditions (e.g. taxa positively or negatively interacting with diazotrophs) and the main abiotic parameters correlating with these interactions in burned and unburned soils. This knowledge would allow to better design and implement soil restoration initiatives in Mediterranean native forest, which will in turn contribute to the reestablishment of proper functionally of the whole forest ecosystem, contributing to sustain their ecosystem services and their natural resilience towards future environmental pressures.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26204\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Instrumento informatizado para el tamizaje de Trastornos Espec\u00edficos del Aprendizaje a trav\u00e9s de la evaluaci\u00f3n de capacidades cognitivas b\u00e1sicas en ni\u00f1os de Educaci\u00f3n General B\u00e1sica (id18i10002)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26204\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26204\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2018 - Junio 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26359\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Children\u0092s development as learner agents through early transitions: exploring the role of playful environments\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26359\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26359\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto integr\u00f3 la participaci\u00f3n de las siguientes estudiantes de la carrera de Pedagog\u00eda en Educaci\u00f3n Parvularia de la Universidad de O'Higgins como asistentes de investigaci\u00f3n:\r\nFernanda L\u00f3pez (cohorte 2018), Daniela Torres (cohorte 2017) y Bel\u00e9n Ortega (cohorte 2017). \r\n\r\nResumen.\r\nEven though the positive impact and results of playful learning during the early years and later school experiences has been recognised by important pedagogues in the history (Froebel, Montessori, Malaguzzi, amongst others); as well as widely researched in more recent developments in the field; this has not yet impacted educators professional training and most important current policy reforms to the early years sector. In addition, years of research in transition processes have widely demonstrated, in a variety of sociocultural contexts, that the objective should be to provide with opportunities of continuity and progression of early childhood pedagogies aligned with children\u0092s learning and developmental processes to promote meaningful learning experiences that will have a long-term impact. However, nowadays school systems around the world are demanding more outcomes from children and their educators. These outcomes are usually measured in learning knowledge content instead of development of abilities. Accordingly, pedagogies in early years levels are increasingly adapting to an adult-centred dynamic which is extremely directive and lacks children\u0092s participation. This is having important consequences in children\u0092s well-being and later adjustment to school. Even though, we know that playful experiences promote learning and positive transitions and consequently are an indicator of good quality provision, in Chile this reality is strongly affecting the so-called transition levels (prekindergarten and kindergarten) which are located inside school premises and therefore, their pedagogies are oriented to readiness for first grade. Therefore, by increasing our understanding of how playful pedagogies can promote: (a) children\u0092s development as learner agents (Dunlop, 2003), and (b) positive transition experiences (Brostr\u00f6m, 2005; Dockett & Perry, 2007), we can contribute with a better articulation of pedagogical practices in early childhood and primary school education.\r\nGoals: this study is based on the understanding of playful learning as essential for positive school transitioning and positive effects for lifelong learning. To identify these practices and its effects on learning the study explores two important factors that research has proven to be related with playful learning: (a) the promotion of guided play in the design of educational environments and learning experiences; and (b) the development of children as learner agents. In sum, the main aim of the study is to establish the relationships between playful pedagogies and children\u0092s development as learner agents during their process of transitioning to formal schooling.\r\nMethodology: this study is a qualitative one drawing on multiple visual participatory methodologies and the application of observational scales. The sample will consist of 12 educational centres, located half in rural communities and half in urban ones. In each centre data will be collected from all children attending pre-kindergarten, kindergarten, first grade and second grade, and their educators and teachers respectively. Within these communities an estimate sample of N=3360 children aged 4 to 8 (35 in each classroom including two groups per level per school) and N=60 practitioners in total will be invited to participate. Analyses will identify playful and academic oriented experiences; measure the types and characteristics of the interactions involved in them; identify and describe how meaning construction occurs during both type of experiences; identify and describe children\u0092s, educators\u0092, and teachers\u0092 perspectives about playful learning experiences. \r\nExpected results: through the application of different measures the expected result is to conclude with a characterization of playful learning episodes that contribute enhancing children\u0092s learning agency during the transition period studied. In addition, it is expected to socialize this result with the wider community of the region, as well as nationally, aiming to advocate for the inclusion of children\u0092s perspectives in the public discussion. Lastly, the objective is to organize a workshop with the participating communities to socialize the results of this study and provide with pedagogical tools to implement playful learning in their educational settings.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2018 - Mayo 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26577\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Brechas de ruralidad en el acceso a la educaci\u00f3n superior\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26577\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26577\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Brechas de ruralidad en el acceso a la educaci\u00f3n superior[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2018 - Octubre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26640\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Dynamic modelling of kiwifruit pollination (Actinidia spp.): effect of temperature on pollen donors and the effective pollination period (EPP)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26640\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26640\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]In this project, the research hypothesis is that in a scenario of climate change (IPCC 2014), the increase of mean air temperature by 2 \u00b0C triggers flowering asynchrony between pollen donors and female cultivars on kiwifruit species (Actinidia spp.) Then, the general objective is to model the impact of temperature changes on interaction between pollen donors and the effective pollination period (EPP) of kiwifruit cultivars (Actinidia spp.). In detail, the specific objectives are: (1) to determine flowering phenology and the effective pollination period (EPP) on kiwifruit cultivars; (2) to evaluate the effect of temperature on sensitivity of pollen-pistil interplay; and (3) to develop a dynamic model of kiwifruit pollination on crop value under potential scenarios of temperature changes.\r\n\r\nThe proposed methodology will be divided in three years. In the first year, flowering phenology of six pollen donors (male cultivars) and two female cultivars (one green-fleshed and other yellow-fleshed) will be characterized. Moreover, in female cultivars the length of time that female flowers can be successfully pollinated, commonly known as the effective pollination period (EPP), will be determined. The EPP may be restricted by limitations in three main events: stigmatic receptivity, pollen tube kinetics and ovule longevity, which will also be evaluated. On the other hand, a dynamic pollination model will be developed using the modeling software Stella\u00ae, based initially on literature review and grower information. \r\nIn the second year, two experiments will be conducted to evaluate the effect of temperature on sensitivity of pollen-pistil interplay: in planta in the field and in vivo in controlled chambers under heat treatments. Consequently, results of all experiments will be integrated on the dynamic pollination model. \r\nFinally, in the third year, after the construction of the model, data of all inputs and outputs will be collected from several kiwifruit orchards of different regions and conditions. Part of these data will be used to find the model weaknesses and to determine how to improve it. The remaining data will be used on cross validation. \r\n\r\nThe main expected result is to determine the vulnerability of interaction between pollen donors and female cultivars by the increase of temperature. The dynamic model of kiwifruit pollination will be permit to predict present and future problems, which will help growers to optimize pollination managements (bee hives and\/or supplemental pollen applications) in the short term. Furthermore, this model can be complemented with other submodels, as thinning, pruning, etc, in order to study simulations of orchard managements. In the long term, these results of heat stress impact on kiwifruit cultivars will be used in further research for establishing new screening criteria of best-adapted genotypes (pollen donors, for example) to Chilean conditions.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26496\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Recreating Market Conditions for Vote-Selling and Vote-Buying in the Lab: The Chilean Case\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26496\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26496\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Desarrollar experimento econ\u00f3mico de clientelismo. Junto a Andrea Canales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2018 - Julio 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26051\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Plataforma geo-referencial predictiva del crecimiento de pradera natural de secano para la gesti\u00f3n sustentable de sistemas pecuarios\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26051\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26051\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2018 - Septiembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26162\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Articulando la vinculaci\u00f3n entre la Universidad de O\u0092Higgins y Establecimientos Educacionales Municipales de la VI Regi\u00f3n, a trav\u00e9s de un estudio de salud mental y resultados acad\u00e9micos en ni\u00f1os del primer ciclo de Ense\u00f1anza B\u00e1sica, y de trabajo ter\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26162\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26162\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo general:\r\n1. Fortalecer la pol\u00edtica institucional de vinculaci\u00f3n con el medio de la UOH, a trav\u00e9s de una\r\nexperiencia piloto de vinculaci\u00f3n con el medio escolar, utilizando como medio una investigaci\u00f3n\r\nsobre salud mental y rendimiento acad\u00e9mico en estudiantes de primer ciclo de Ense\u00f1anza\r\nB\u00e1sica, a trav\u00e9s de una estrategia de colaboraci\u00f3n entre actores educacionales, comunitarios y\r\nacad\u00e9micos, bajo una perspectiva de trabajo territorial.\r\nObjetivos espec\u00edficos:\r\n1. Fortalecer la pol\u00edtica institucional de vinculaci\u00f3n con el medio de la UOH, a trav\u00e9s del desarrollo\r\nde una experiencia piloto que articula el trabajo de actores educacionales, comunitarios y\r\nacad\u00e9micos, en contextos territoriales espec\u00edficos.\r\n2. Desarrollar una investigaci\u00f3n que potencie la estrategia de vinculaci\u00f3n con el medio a trav\u00e9s de\r\nun problema relevante y sentido por la comunidad, cuya finalidad ser\u00e1 identificar la presencia\r\nde un problema de salud mental en estudiantes del primer ciclo de la Ense\u00f1anza B\u00e1sica de\r\nestablecimientos municipales de la Regi\u00f3n de O\u0092Higgins y establecer su asociaci\u00f3n con el\r\nrendimiento acad\u00e9mico de estos.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2018 - Noviembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26275\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desarrollo de un sistema p\u00fablico de alerta temprana para proveer de avisos de aplicaci\u00f3n oportunos para el control de Eulias en frutales y vi\u00f1as\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26275\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26275\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proeulia auraria (eulia de los frutales=EF) es una especie nativa que ataca la mayor\u00eda de los frutales (carozos, pom\u00e1ceas, vides, berries, etc) convirti\u00e9ndose en una plaga cada vez m\u00e1s relevante. Su fenolog\u00eda incluye 2 generaciones por temporada; la primera afecta brotaci\u00f3n y floraci\u00f3n, y la segunda cuaja-cosecha. Las larvas consumen follaje, flores y frutos (hasta un 30%). Adem\u00e1s, es la quinta o sexta plaga cuarentenaria en exportaciones chilenas, causando todas las temporadas abundantes rechazos (entre 1 a 9% del total; fuente SAG). Ello hace indispensable controlar EF con aplicaciones de insecticidas residuales. Las ventanas de aplicaci\u00f3n deben ser precisadas para optimizar el control y el uso de plaguicidas (ovicidas o larvicidas). Por tanto, es necesario predecir eventos cr\u00edticos con modelos fenol\u00f3gicos, lo cual no se ha desarrollado contra esta especie. Los modelos requieren estimar umbrales t\u00e9rmicos (superior e inferior, UTS y UTI respectivamente) y la acumulaci\u00f3n t\u00e9rmica (grados-d\u00eda o &#8721;GD) por estadio. El UTI y la &#8721;GD se estimaron previamente (2010-2012) para EF en un proyecto RED DE PRON\u00d3STICOS FITOSANITARIOS RPF del SAG (ID-6que 12-2737-SE10), evaluando 5 reg\u00edmenes de temperatura entre 13 y 28\u00b0C. Sin embargo, no se estableci\u00f3 el UTS y el modelo preliminar que deriv\u00f3 del estudio, se desv\u00eda parcialmente de lo observado. La presente propuesta de la U. de Chile plantea dise\u00f1ar un sistema de alerta temprana de precisi\u00f3n para el control eficiente de EF, para lo cual se verificar\u00e1\/modificar\u00e1 el UTI y la &#8721;GD por estadio, y se determinar\u00e1 el UTS (con modelos no lineales), criando cohortes de los diferentes estados del insecto en 4 reg\u00edmenes de temperatura adicionales (7, 10, 31, 33\u00b0C), en condiciones similares a las usadas en el estudio previo, lo que mejorar\u00e1 la calidad de los ajustes. Luego, se determinar\u00e1 la forma de c\u00e1lculo de los GD, contrastando las observaciones de campo con la predicci\u00f3n del modelo, tanto para el corte vertical como el horizontal, y se seleccionar\u00e1 aqu\u00e9l que tenga mayor correlaci\u00f3n, no realizado en el estudio previo. De la misma manera se determinar\u00e1 un Biofix o evento que indica cu\u00e1ndo se debe\r\niniciar el c\u00e1lculo de GD en campo. Estos modelos tambi\u00e9n requieren estimar con la mayor precisi\u00f3n el calor experimentado por los insectos. La propuesta plantea usar sensores de temperatura en distintas posiciones de la copa, de 4 especies frutales hospederas de EF, para determinar un factor de correcci\u00f3n que permita ajustar el modelo de GD para EF. Esta informaci\u00f3n permitir\u00e1 desarrollar algoritmos con los que se har\u00e1n las predicciones del Sistema de Alerta del SAG (RPF), generando pron\u00f3sticos a 8 d\u00edas. Para hacer accesible el sistema, se aprovechar\u00e1 el Portal Productor del RPF-SAG, para ofrecer el servicio de alerta temprana de Eulia a los productores.\r\nEl sistema de alerta para EF quedar\u00e1 programado y disponible para que todos los usuarios, sin costo, puedan dibujar los pol\u00edgonos a nivel de cuartel y variedad para programar sus alertas y controles qu\u00edmicos, rompiendo la brecha de cobertura y acceso a informaci\u00f3n meteorol\u00f3gica, y de recomendaciones de manejo, que existe entre productores.\r\nLa transferencia tecnol\u00f3gica a los usuarios finales, se realizar\u00e1 mediante actividades de capacitaci\u00f3n, seminarios, d\u00edas de campo y un manual de uso que quedar\u00e1 a su disposici\u00f3n. La sustentabilidad del proyecto estar\u00e1 garantizada por la mantenci\u00f3n del servicio en la plataforma RPF, por el SAG.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2018 - Diciembre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26304\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Red colaborativa para el estudio de enfermedades en trabajadores agr\u00edcolas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26304\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26304\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2018 - Septiembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26408\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Articulando la vinculaci\u00f3n entre la Universidad de O\u0092Higgins y Establecimientos Educacionales Municipales de la VI Regi\u00f3n, a trav\u00e9s de un estudio de salud mental y resultados acad\u00e9micos en ni\u00f1os del primer ciclo de Ense\u00f1anza B\u00e1sica, y de trabajo ter\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26408\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26408\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo general:\r\n1. Fortalecer la pol\u00edtica institucional de vinculaci\u00f3n con el medio de la UOH, a trav\u00e9s de una\r\nexperiencia piloto de vinculaci\u00f3n con el medio escolar, utilizando como medio una investigaci\u00f3n\r\nsobre salud mental y rendimiento acad\u00e9mico en estudiantes de primer ciclo de Ense\u00f1anza\r\nB\u00e1sica, a trav\u00e9s de una estrategia de colaboraci\u00f3n entre actores educacionales, comunitarios y\r\nacad\u00e9micos, bajo una perspectiva de trabajo territorial.\r\nObjetivos espec\u00edficos:\r\n1. Fortalecer la pol\u00edtica institucional de vinculaci\u00f3n con el medio de la UOH, a trav\u00e9s del desarrollo\r\nde una experiencia piloto que articula el trabajo de actores educacionales, comunitarios y\r\nacad\u00e9micos, en contextos territoriales espec\u00edficos.\r\n2. Desarrollar una investigaci\u00f3n que potencie la estrategia de vinculaci\u00f3n con el medio a trav\u00e9s de\r\nun problema relevante y sentido por la comunidad, cuya finalidad ser\u00e1 identificar la presencia\r\nde un problema de salud mental en estudiantes del primer ciclo de la Ense\u00f1anza B\u00e1sica de\r\nestablecimientos municipales de la Regi\u00f3n de O\u0092Higgins y establecer su asociaci\u00f3n con el\r\nrendimiento acad\u00e9mico de estos.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2018 - Marzo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26485\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Understanding the role of global change in forest dynamics of endemic trees in central Chile: generating knowledge for their conservation and restoration\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26485\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26485\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El aumento en las condiciones de sequ\u00eda experimentadas en el centro de Chile durante el\r\n\u00faltimo siglo ha sido poco estudiado en t\u00e9rminos de sus posibles impactos en la din\u00e1mica\r\nforestal de los bosques mediterr\u00e1neos de Chile central. Se ha observado una disminuci\u00f3n del\r\ncrecimiento y una pobre regeneraci\u00f3n por semilla, que se asociar\u00eda con los cambios en los\r\npatrones clim\u00e1ticos. El presente proyecto busca evaluar desde una perspectiva hist\u00f3rica la\r\nrespuesta de los \u00e1rboles mediterr\u00e1neos de Chile frente al cambio global reciente, utilizando\r\nespecies perennes (bosques escler\u00f3filos) y caducifolios (bosques de Nothofagus) en un\r\ngradiente altitudinal y latitudinal (30\u00b0-35\u00b0 S), complementando con estudios retrospectivos\r\n(an\u00e1lisis dendrocronol\u00f3gico e isot\u00f3pico) y estudios prospectivos (an\u00e1lisis en c\u00e1maras de\r\ncrecimiento controlado). Los resultados proporcionar\u00e1n informaci\u00f3n valiosa para\r\ncomprender la resiliencia ecol\u00f3gica de los ecosistemas mediterr\u00e1neos de Am\u00e9rica del Sur y,\r\npor lo tanto, ser\u00e1n \u00fatiles para futuros programas de conservaci\u00f3n y restauraci\u00f3n ecol\u00f3gica.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2018 - Septiembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26576\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Articulando la vinculaci\u00f3n entre la Universidad de O\u0092Higgins y Establecimientos Educacionales Municipales de la VI Regi\u00f3n, a trav\u00e9s de un estudio de salud mental y resultados acad\u00e9micos en ni\u00f1os del primer ciclo de Ense\u00f1anza B\u00e1sica, y de trabajo ter\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26576\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26576\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo general:\r\n1. Fortalecer la pol\u00edtica institucional de vinculaci\u00f3n con el medio de la UOH, a trav\u00e9s de una\r\nexperiencia piloto de vinculaci\u00f3n con el medio escolar, utilizando como medio una investigaci\u00f3n\r\nsobre salud mental y rendimiento acad\u00e9mico en estudiantes de primer ciclo de Ense\u00f1anza\r\nB\u00e1sica, a trav\u00e9s de una estrategia de colaboraci\u00f3n entre actores educacionales, comunitarios y\r\nacad\u00e9micos, bajo una perspectiva de trabajo territorial.\r\nObjetivos espec\u00edficos:\r\n1. Fortalecer la pol\u00edtica institucional de vinculaci\u00f3n con el medio de la UOH, a trav\u00e9s del desarrollo\r\nde una experiencia piloto que articula el trabajo de actores educacionales, comunitarios y\r\nacad\u00e9micos, en contextos territoriales espec\u00edficos.\r\n2. Desarrollar una investigaci\u00f3n que potencie la estrategia de vinculaci\u00f3n con el medio a trav\u00e9s de\r\nun problema relevante y sentido por la comunidad, cuya finalidad ser\u00e1 identificar la presencia\r\nde un problema de salud mental en estudiantes del primer ciclo de la Ense\u00f1anza B\u00e1sica de\r\nestablecimientos municipales de la Regi\u00f3n de O\u0092Higgins y establecer su asociaci\u00f3n con el\r\nrendimiento acad\u00e9mico de estos.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11180278<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2018 - Marzo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26626\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Root system architecture traits of Lagenaria siceraria are key  phenes for selection under drought stress condition in grafted  plants of watermelon (Citrullus lanatus)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26626\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26626\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Chile is one of the principal producer and exporter country of fruit and vegetable crops in the southern\r\nhemisphere. In both fruit and vegetable crops there are an increasing concern about agriculture sustainability\r\nthat includes the evaluation and implementation of practices with lower environmental impact. In this\r\ncontext, and considering the modern vegetable crop production, the use of rootstocks is being considered an\r\nessential component due to their ability to adapt a particular cultivar to diverse environmental conditions\r\nand\/or cultural practices.\r\nIn agriculture, rootstocks have been used since over 2000 years ago. Specifically, in cucurbits, the most\r\ngrafted vegetable crops are watermelon, melon and cucumber. For watermelon, Lagenaria siceraria (bottle\r\ngourd) has been used in different countries as one of the main rootstocks. Considering the recent agricultural\r\nscenario, in which drought represent the major risk that impacts negatively the production of major and\r\nminor crops, the rootstocks development and the understanding of the role of key root traits would help to\r\nassist breeders for drought tolerance landraces selection. In fact, the effects of water regime or deficit on\r\nroot system development of bottle gourd is not well understood, in addition, the underlying phenotypic and\r\ngenotypic variability of bottle gourd with respect to root system architecture parameters has not been welldocumented.\r\nA crucial component of roots is their architecture, which refers to the spatial-temporal extension of the entire\r\nroot system in the soil, the root system architecture (RSA). RSA traits, or phenes, has been shown to be\r\nimportant in agricultural systems, in fact, it is considered relevant for improve selection in fruit and vegetable\r\nrootstocks breeding programs. Understanding the contribution of specific RSA traits to root system function\r\nis critical, and plays a pivotal role in crop performance because it allows the identification of keys traits that\r\ncontribute in desired functions, and consequently could be considered for developing crops with more efficient\r\nroots.\r\nIn this proposal it is hypothesized that, landraces of Lagenaria siceraria shows high phenotypic and genotypic\r\nvariation for RSA traits like Root Growth Angle (RGA) and Roots System Depth (RSD). In turn, these phenes\r\nare positively correlated with drought tolerance and therefore useful to develop rootstocks with this\r\ncharacteristic in Lagenaria siceraria. In addition, it is also hypothesized that selected L. siceraria rootstocks\r\nare able to confer to grafted varieties of watermelon (Citrullus lanatus) an enhanced tolerance to drought.\r\nFor that, the main goal is to evaluate the root system architecture as parameter of selection for drought\r\ntolerance in different Lagenaria siceraria landraces and in grafted plants of watermelon (Citrullus lanatus).\r\nThe specific goals are: 1. To assess the phenotypic and genotypic variation of Lagenaria siceraria landraces\r\nby using root system architecture parameters and genotyping-by-sequencing through SNP markers; 2. To\r\ndetermine the root system architecture parameters that help into the selection of Lagenaria siceraria under\r\ndrought stress condition; 3. To characterize the response to drought stress of watermelon grafted onto\r\nLagenaria siceraria landraces under field conditions after the selection through the root system architecture\r\nparameters.\r\nTo reach this goals it is proposing the phenotypic characterization of root traits (phenes) in Lagenaria siceraria\r\nlandraces in a greenhouse under drought stress condition. The genotypic variation of bottle gourd will be\r\nstudied by using Genotyping-by-sequencing, principal component analysis and genetic relatedness (identityby-state). A multivariate statistical analysis will be implemented to select key root phenes which will be used\r\nto evaluate the selection of L. siceraria in a rootstock breeding program. These root phenes will be\r\ncharacterized in grafted plants of watermelon into L. siceraria under field conditions by using the shovelomics\r\nphenotyping method.\r\nThis proposal expects to contribute with the knowledge of genotypic and phenotypic variation in bottle gourd\r\nfor root system architecture traits, and to identify the possibilities that offers the key root phenes to screen\r\nrootstocks for drought tolerance. These results would be relevant for the selection and breeding of cucurbits\r\nrootstock with better tolerance to drought. It is also expected that some of these Lagenaria siceraria\r\nlandraces will be important rootstock for watermelon under semi-arid conditions of Chile.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2018 - Octubre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26639\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desarrollo de una metodolog\u00eda predictiva para la estimaci\u00f3n de calibre en kiwi\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26639\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26639\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto forma parte del Programa Tecnol\u00f3gico para la Fruticultura de Exportaci\u00f3n Zona Centro-Sur 16PTECFS-6641 Especie Kiwi, Coejecutores:  Consorcio de la Fruta - Pontificia Universidad Cat\u00f3lica \r\nEl objetivo general es identificar, evaluar y desarrollar una metodolog\u00eda que permita determinar la\r\ndistribuci\u00f3n de calibre en kiwi, variedad Hayward.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2018 - Septiembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26675\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Articulando la vinculaci\u00f3n entre la Universidad de O\u0092Higgins y Establecimientos Educacionales Municipales de la VI Regi\u00f3n, a trav\u00e9s de un estudio de salud mental y resultados acad\u00e9micos en ni\u00f1os del primer ciclo de Ense\u00f1anza B\u00e1sica, y de trabajo ter\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26675\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26675\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo general:\r\n1. Fortalecer la pol\u00edtica institucional de vinculaci\u00f3n con el medio de la UOH, a trav\u00e9s de una\r\nexperiencia piloto de vinculaci\u00f3n con el medio escolar, utilizando como medio una investigaci\u00f3n\r\nsobre salud mental y rendimiento acad\u00e9mico en estudiantes de primer ciclo de Ense\u00f1anza\r\nB\u00e1sica, a trav\u00e9s de una estrategia de colaboraci\u00f3n entre actores educacionales, comunitarios y\r\nacad\u00e9micos, bajo una perspectiva de trabajo territorial.\r\nObjetivos espec\u00edficos:\r\n1. Fortalecer la pol\u00edtica institucional de vinculaci\u00f3n con el medio de la UOH, a trav\u00e9s del desarrollo\r\nde una experiencia piloto que articula el trabajo de actores educacionales, comunitarios y\r\nacad\u00e9micos, en contextos territoriales espec\u00edficos.\r\n2. Desarrollar una investigaci\u00f3n que potencie la estrategia de vinculaci\u00f3n con el medio a trav\u00e9s de\r\nun problema relevante y sentido por la comunidad, cuya finalidad ser\u00e1 identificar la presencia\r\nde un problema de salud mental en estudiantes del primer ciclo de la Ense\u00f1anza B\u00e1sica de\r\nestablecimientos municipales de la Regi\u00f3n de O\u0092Higgins y establecer su asociaci\u00f3n con el\r\nrendimiento acad\u00e9mico de estos.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2018 - Octubre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26716\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            El tratamiento informativo de los inmigrantes en la prensa nacional escrita actual (2015-2019) y su impacto en la opini\u00f3n p\u00fablica\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26716\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26716\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El tema de inmigraci\u00f3n es de gran importancia para Chile. M\u00e1s a\u00fan en la actualidad, cuando se vive un aumento significativo de los flujos migratorios, tanto de los pa\u00edses vecinos, como Per\u00fa, Colombia y Venezuela, como de pa\u00edses lejanos como Hait\u00ed (Rojas et al., 2015). Este hecho, sin lugar a dudas, tiene su reflejo en los medios de comunicaci\u00f3n donde, casi diariamente, programas de radio, televisi\u00f3n y art\u00edculos de prensa tratan el tema de los inmigrantes. \r\nEl argumento principal de esta propuesta se basa en que la construcci\u00f3n de la opini\u00f3n p\u00fablica acerca de ciertos temas se hace parcialmente a partir de las noticias publicadas en los medios de comunicaci\u00f3n (D'Adamo & Garc\u00eda, 2003). M\u00e1s en concreto, se basa en que los medios de comunicaci\u00f3n proporcionan una serie de encuadres noticiosos que sirven como referencia a la opini\u00f3n p\u00fablica para interpretar y discutir sobre ciertos temas (Igartua et al., 2005).\r\nDicho esto, el presente proyecto establece como objetivo general analizar el tratamiento informativo de los inmigrantes en la prensa nacional escrita actual (2015-2019) y su influencia en la opini\u00f3n p\u00fablica. A partir de este objetivo generamos tres objetivos espec\u00edficos: \r\n1. Identificar y analizar los encuadres noticiosos en la prensa nacional escrita actual (2015-2019) en Chile a la hora de cubrir el tema de los inmigrantes. \r\n2. Comparar los encuadres noticiosos en la prensa nacional escrita actual (2015-2019) en Chile a la hora de cubrir el tema de los inmigrantes.\r\n3. Comparar la relaci\u00f3n (similitud y\/o diferencia) entre los encuadres noticiosos que dominan en la prensa nacional escrita actual (2015-2019) en Chile a la hora de cubrir el tema de los inmigrantes y la opini\u00f3n p\u00fablica sobre este tema.\r\nPara cumplir con estos objetivos trabajaremos con la muestra general del estudio que incluir\u00e1 los textos, cuyo tema central del discurso son los inmigrantes, publicados en tres peri\u00f3dicos nacionales (El Mercurio, La Tercera y Publimetro) durante el periodo 2015-2019. As\u00ed pues, para cumplir con los objetivos espec\u00edficos 1 y 2 aplicaremos an\u00e1lisis de contenido y an\u00e1lisis comparativo como metodolog\u00eda de trabajo. A su vez, para cumplir con el objetivo espec\u00edfico 3, usaremos una encuesta dirigida y aplicada al p\u00fablico general (como m\u00ednimo 500 personas) de nacionalidad chilena. \r\nCon los resultados de este proyecto se pretende contribuir al conocimiento del estado actual del tratamiento informativo de los inmigrantes en la prensa escrita actual y su influencia en la opini\u00f3n p\u00fablica. Y en espec\u00edfico, se entregar\u00e1 conocimiento sobre la relaci\u00f3n entre los peri\u00f3dicos que lee el p\u00fablico y lo que piensa sobre los inmigrantes en el pa\u00eds. \r\nM\u00e1s a\u00fan, los resultados pueden ser de inter\u00e9s para el Ministerio del Interior y Seguridad P\u00fablica para proyectar pol\u00edticas p\u00fablicas con respecto a la tem\u00e1tica y, sobre todo, a la prevenci\u00f3n del racismo y xenofobia en el pa\u00eds. Seg\u00fan van Dijk (1997), los medios de comunicaci\u00f3n pueden influir en los modelos mentales que construye el p\u00fablico sobre los inmigrantes, lo que en su versi\u00f3n extrema puede provocar ciertos perjuicios, racismo y xenofobia. Con este proyecto, queremos llamar la atenci\u00f3n sobre las tem\u00e1ticas migratorias en Chile para evitar la triste experiencia que se vivi\u00f3 en Europa hace una d\u00e9cada, donde las numerosas investigaciones demostraron el papel de los medios de comunicaci\u00f3n en el establecimiento de racismo y xenofobia hacia el otro (van Dijk, 1997). No queremos vivir la misma experiencia en Chile, y por eso, debemos tomar las medidas desde el principio para evitar las fatales consecuencias en el futuro. \r\nCon los resultados cient\u00edficos de este proyecto pretendemos evidenciar emp\u00edricamente el \u0093comportamiento\u0094 de los medios de comunicaci\u00f3n, en concreto, de la prensa nacional escrita, a la hora de cubrir el tema de los inmigrantes para as\u00ed levantar la conciencia de los hechos y sus efectos socio-cognitivos en la poblaci\u00f3n chilena.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2018 - Septiembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26825\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Articulando la vinculaci\u00f3n entre la Universidad de O\u0092Higgins y Establecimientos Educacionales Municipales de la VI Regi\u00f3n, a trav\u00e9s de un estudio de salud mental y resultados acad\u00e9micos en ni\u00f1os del primer ciclo de Ense\u00f1anza B\u00e1sica, y de trabajo ter\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26825\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26825\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo general:\r\n1. Fortalecer la pol\u00edtica institucional de vinculaci\u00f3n con el medio de la UOH, a trav\u00e9s de una\r\nexperiencia piloto de vinculaci\u00f3n con el medio escolar, utilizando como medio una investigaci\u00f3n\r\nsobre salud mental y rendimiento acad\u00e9mico en estudiantes de primer ciclo de Ense\u00f1anza\r\nB\u00e1sica, a trav\u00e9s de una estrategia de colaboraci\u00f3n entre actores educacionales, comunitarios y\r\nacad\u00e9micos, bajo una perspectiva de trabajo territorial.\r\nObjetivos espec\u00edficos:\r\n1. Fortalecer la pol\u00edtica institucional de vinculaci\u00f3n con el medio de la UOH, a trav\u00e9s del desarrollo\r\nde una experiencia piloto que articula el trabajo de actores educacionales, comunitarios y\r\nacad\u00e9micos, en contextos territoriales espec\u00edficos.\r\n2. Desarrollar una investigaci\u00f3n que potencie la estrategia de vinculaci\u00f3n con el medio a trav\u00e9s de\r\nun problema relevante y sentido por la comunidad, cuya finalidad ser\u00e1 identificar la presencia\r\nde un problema de salud mental en estudiantes del primer ciclo de la Ense\u00f1anza B\u00e1sica de\r\nestablecimientos municipales de la Regi\u00f3n de O\u0092Higgins y establecer su asociaci\u00f3n con el\r\nrendimiento acad\u00e9mico de estos.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2018 - Febrero 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26348\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Sweet Pekeetah: Un modelo tecnol\u00f3gico-comercial para una nueva variedad chilena de fruta\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26348\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26348\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetivo general es desarrollar una propuesta de estrategia de marketing y modelo de negocio de producto de la variedad de ciruela japonesa \u0093Sweet Pekeetah\u0094, destacando su alta calidad sensorial y su potencial de poscosecha, a trav\u00e9s del dise\u00f1o de un protocolo de manejo agron\u00f3mico y almacenamiento.\r\nLos objetivos espec\u00edficos, corresponden a:\r\n1.\tDesarrollar un protocolo de producci\u00f3n y de almacenamiento para la ciruela \u0093Sweet Pekeetah\u0094 que permita optimizar la productividad y mantener los atributos organol\u00e9pticos destacados de la variedad por periodos de conservaci\u00f3n prolongados.\r\n2.\tRealizar un an\u00e1lisis del potencial de lanzamiento comercial de la variedad \u0093Sweet Pekeetah\u0094 entre intermediarios (exportadores y distribuidores), examinando los elementos cr\u00edticos que se requieren para su estrategia de distribuci\u00f3n y de marca. \r\n3.\tEvaluar la recepci\u00f3n de los consumidores finales de la nueva variedad de ciruela \u0093Sweet Pekeetah\u0094, particularmente estableciendo sus diferencias perceptuales con la oferta presente en el mercado. \r\n4.\tEstablecer una denominaci\u00f3n (marca) para la variedad \u0093Sweet Pekeetah\u0094 y determinar el valor agregado que entrega este elemento sobre la fruta en el mercado. \r\n\r\nDentro de los resultados esperados:\r\n1.\tPaquete tecnol\u00f3gico con \u00e9nfasis en la polinizaci\u00f3n, carga frutal, \u00edndices de cosecha y postcosecha para obtener un producto de \u00f3ptima calidad sensorial en mercados distantes.\r\n2.\tInforme de la evaluaci\u00f3n de la percepci\u00f3n de consumidores europeos, norteamericanos y chinos sobre el grado de aceptabilidad de la variedad \u0093Sweet Pekeetah\u0094.\r\n3.\tInforme de la evaluaci\u00f3n del efecto de una marca e imagen asociada a la variedad \u0093Sweet Pekeetah\u0094 sobre la disposici\u00f3n a pago de consumidores en diferentes mercados.\r\n4.\tModelo de negocios para desarrollar la variedad \u0093Sweet Pekeetah\u0094 en un formato de club exclusivo que asegure su sustentaci\u00f3n en el largo plazo.\r\n5.\tPatentamiento de la variedad \u0093Sweet Pekeetah\u0094 en pa\u00edses del hemisferio norte, para su desarrollo comercial posterior.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2018 - Diciembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26826\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Atenci\u00f3n Primaria de la Salud: evaluaci\u00f3n de una intervenci\u00f3n comunitaria para la adherencia a tratamiento de pacientes con diagn\u00f3stico de hipertensi\u00f3n arterial y\/o diabetes\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26826\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26826\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2018 - Diciembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26019\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Los procesos de ense\u00f1anza y evaluaci\u00f3n en el \u00e1rea de salud en grado y posgrado y su vinculaci\u00f3n con el rendicimiento acad\u00e9mico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26019\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26019\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto de investigaci\u00f3n focaliza en la ense\u00f1anza, evaluaci\u00f3n y rendimiento acad\u00e9mico en el \u00e1rea de salud en laFacultad de Ciencias M\u00e9dicas de la UNC y la Escuela de Salud de la Universidad de O'Higgins-Chile (UOH). El mismoaborda diversos procesos formativos de carreras de grado y posgrado, y se organiza en tres l\u00edneas de investigaci\u00f3n quese articulan entre s\u00ed, una ligada a las trayectorias acad\u00e9micas de los estudiantes de grado y posgrado, otra orientada alsistema de evaluaci\u00f3n en grado y posgrado y una tercera referida a la relaci\u00f3n entre formaci\u00f3n pedag\u00f3gica-disciplinary docente asistencial como as\u00ed tambi\u00e9n su vinculaci\u00f3n con la ense\u00f1anza y evaluaci\u00f3n.Se proponen los siguientesobjetivos: analizar los procesos de ense\u00f1anza y evaluaci\u00f3n en carreras del \u00e1rea de salud en grado y posgrado y surelaci\u00f3n con la trayectoria acad\u00e9mica de los estudiantes por un lado y por otro la relaci\u00f3n entre formaci\u00f3n pedag\u00f3gica- disciplinar -docente?asistencial articulando con los procesos de ense\u00f1anza y evaluaci\u00f3n.Para abordar los objetivos se realizar\u00e1 un an\u00e1lisis longitudinal prospectivo de las cohortes de ingresantes a la Escuela de Tecnolog\u00eda M\u00e9dica, laCarrera de Medicina de la UNC y a la Escuela de Salud (UOH). El registro se efectuar\u00e1 a 1400 estudiantes en la UNCy a 95 en la UOH (2017-2018). Se realizar\u00e1 un estudio de correlaci\u00f3n y comparaci\u00f3n entre la calificaci\u00f3n obtenida enla evaluaci\u00f3n diagn\u00f3stica y los resultados del examen final al t\u00e9rmino de la PFO, incluye 514 estudiantes.Tambi\u00e9nse abordar\u00e1 el sistema de evaluaci\u00f3n de 17 especialidades m\u00e9dicas acreditadas (2018-2020) y la relaci\u00f3n entreformaci\u00f3n pedag\u00f3gica-disciplinar-docente-asistencial en grado y posgrado en ambas universidades. Se implementar\u00e1ncuestionarios abiertos y entrevistas. El an\u00e1lisis de la informaci\u00f3n se llevar\u00e1 a cabo desde un abordaje cuantitativo ycualitativo. Desde lo cuantitativo se propone la combinaci\u00f3n de diferentes m\u00e9todos multivariado, test de comparacionesy datos categorizados, que permitir\u00e1n abordar las variables involucradas tanto exploratoriamente como de manerainferencial. Se utilizar\u00e1 el coeficiente de correlaci\u00f3n lineal de Pearson, el modelo de regresi\u00f3n lineal y se calcular\u00e1el Coeficiente de Cp de Mallows, con un nivel de significaci\u00f3n de 0,05 para todos los casos. Lo cualitativo permitir\u00e1comprender experiencias y perspectivas de los sujetos, la construcci\u00f3n de la teor\u00eda a trav\u00e9s de los hallazgos y lavalidaci\u00f3n mediante el proceso de triangulaci\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2018 - Enero 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26075\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Diagn\u00f3stico de formaci\u00f3n inicial docente en la Universidad de O\u0092Higgins y dise\u00f1o de un plan de implementaci\u00f3n para su fortalecimiento\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26075\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26075\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2018 - Enero 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26163\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Diagn\u00f3stico de formaci\u00f3n inicial docente en la Universidad de O\u0092Higgins y dise\u00f1o de un plan de implementaci\u00f3n para su fortalecimiento\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26163\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26163\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2018 - Enero 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26203\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Diagn\u00f3stico de formaci\u00f3n inicial docente en la Universidad de O\u0092Higgins y dise\u00f1o de un plan de implementaci\u00f3n para su fortalecimiento\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26203\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26203\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2018 - Enero 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26523\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Diagn\u00f3stico de formaci\u00f3n inicial docente en la Universidad de O\u0092Higgins y dise\u00f1o de un plan de implementaci\u00f3n para su fortalecimiento\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26523\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26523\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2018 - Diciembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26676\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Los procesos de ense\u00f1anza y evaluaci\u00f3n en el \u00e1rea de salud en grado y posgrado y su vinculaci\u00f3n con el rendicimiento acad\u00e9mico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26676\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26676\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto de investigaci\u00f3n focaliza en la ense\u00f1anza, evaluaci\u00f3n y rendimiento acad\u00e9mico en el \u00e1rea de salud en laFacultad de Ciencias M\u00e9dicas de la UNC y la Escuela de Salud de la Universidad de O'Higgins-Chile (UOH). El mismoaborda diversos procesos formativos de carreras de grado y posgrado, y se organiza en tres l\u00edneas de investigaci\u00f3n quese articulan entre s\u00ed, una ligada a las trayectorias acad\u00e9micas de los estudiantes de grado y posgrado, otra orientada alsistema de evaluaci\u00f3n en grado y posgrado y una tercera referida a la relaci\u00f3n entre formaci\u00f3n pedag\u00f3gica-disciplinary docente asistencial como as\u00ed tambi\u00e9n su vinculaci\u00f3n con la ense\u00f1anza y evaluaci\u00f3n.Se proponen los siguientesobjetivos: analizar los procesos de ense\u00f1anza y evaluaci\u00f3n en carreras del \u00e1rea de salud en grado y posgrado y surelaci\u00f3n con la trayectoria acad\u00e9mica de los estudiantes por un lado y por otro la relaci\u00f3n entre formaci\u00f3n pedag\u00f3gica- disciplinar -docente?asistencial articulando con los procesos de ense\u00f1anza y evaluaci\u00f3n.Para abordar los objetivos se realizar\u00e1 un an\u00e1lisis longitudinal prospectivo de las cohortes de ingresantes a la Escuela de Tecnolog\u00eda M\u00e9dica, laCarrera de Medicina de la UNC y a la Escuela de Salud (UOH). El registro se efectuar\u00e1 a 1400 estudiantes en la UNCy a 95 en la UOH (2017-2018). Se realizar\u00e1 un estudio de correlaci\u00f3n y comparaci\u00f3n entre la calificaci\u00f3n obtenida enla evaluaci\u00f3n diagn\u00f3stica y los resultados del examen final al t\u00e9rmino de la PFO, incluye 514 estudiantes.Tambi\u00e9nse abordar\u00e1 el sistema de evaluaci\u00f3n de 17 especialidades m\u00e9dicas acreditadas (2018-2020) y la relaci\u00f3n entreformaci\u00f3n pedag\u00f3gica-disciplinar-docente-asistencial en grado y posgrado en ambas universidades. Se implementar\u00e1ncuestionarios abiertos y entrevistas. El an\u00e1lisis de la informaci\u00f3n se llevar\u00e1 a cabo desde un abordaje cuantitativo ycualitativo. Desde lo cuantitativo se propone la combinaci\u00f3n de diferentes m\u00e9todos multivariado, test de comparacionesy datos categorizados, que permitir\u00e1n abordar las variables involucradas tanto exploratoriamente como de manerainferencial. Se utilizar\u00e1 el coeficiente de correlaci\u00f3n lineal de Pearson, el modelo de regresi\u00f3n lineal y se calcular\u00e1el Coeficiente de Cp de Mallows, con un nivel de significaci\u00f3n de 0,05 para todos los casos. Lo cualitativo permitir\u00e1comprender experiencias y perspectivas de los sujetos, la construcci\u00f3n de la teor\u00eda a trav\u00e9s de los hallazgos y lavalidaci\u00f3n mediante el proceso de triangulaci\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2018 - Enero 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26715\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Diagn\u00f3stico de formaci\u00f3n inicial docente en la Universidad de O\u0092Higgins y dise\u00f1o de un plan de implementaci\u00f3n para su fortalecimiento\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26715\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26715\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2018 - Diciembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26829\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Los procesos de ense\u00f1anza y evaluaci\u00f3n en el \u00e1rea de salud en grado y posgrado y su vinculaci\u00f3n con el rendicimiento acad\u00e9mico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26829\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26829\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto de investigaci\u00f3n focaliza en la ense\u00f1anza, evaluaci\u00f3n y rendimiento acad\u00e9mico en el \u00e1rea de salud en laFacultad de Ciencias M\u00e9dicas de la UNC y la Escuela de Salud de la Universidad de O'Higgins-Chile (UOH). El mismoaborda diversos procesos formativos de carreras de grado y posgrado, y se organiza en tres l\u00edneas de investigaci\u00f3n quese articulan entre s\u00ed, una ligada a las trayectorias acad\u00e9micas de los estudiantes de grado y posgrado, otra orientada alsistema de evaluaci\u00f3n en grado y posgrado y una tercera referida a la relaci\u00f3n entre formaci\u00f3n pedag\u00f3gica-disciplinary docente asistencial como as\u00ed tambi\u00e9n su vinculaci\u00f3n con la ense\u00f1anza y evaluaci\u00f3n.Se proponen los siguientesobjetivos: analizar los procesos de ense\u00f1anza y evaluaci\u00f3n en carreras del \u00e1rea de salud en grado y posgrado y surelaci\u00f3n con la trayectoria acad\u00e9mica de los estudiantes por un lado y por otro la relaci\u00f3n entre formaci\u00f3n pedag\u00f3gica- disciplinar -docente?asistencial articulando con los procesos de ense\u00f1anza y evaluaci\u00f3n.Para abordar los objetivos se realizar\u00e1 un an\u00e1lisis longitudinal prospectivo de las cohortes de ingresantes a la Escuela de Tecnolog\u00eda M\u00e9dica, laCarrera de Medicina de la UNC y a la Escuela de Salud (UOH). El registro se efectuar\u00e1 a 1400 estudiantes en la UNCy a 95 en la UOH (2017-2018). Se realizar\u00e1 un estudio de correlaci\u00f3n y comparaci\u00f3n entre la calificaci\u00f3n obtenida enla evaluaci\u00f3n diagn\u00f3stica y los resultados del examen final al t\u00e9rmino de la PFO, incluye 514 estudiantes.Tambi\u00e9nse abordar\u00e1 el sistema de evaluaci\u00f3n de 17 especialidades m\u00e9dicas acreditadas (2018-2020) y la relaci\u00f3n entreformaci\u00f3n pedag\u00f3gica-disciplinar-docente-asistencial en grado y posgrado en ambas universidades. Se implementar\u00e1ncuestionarios abiertos y entrevistas. El an\u00e1lisis de la informaci\u00f3n se llevar\u00e1 a cabo desde un abordaje cuantitativo ycualitativo. Desde lo cuantitativo se propone la combinaci\u00f3n de diferentes m\u00e9todos multivariado, test de comparacionesy datos categorizados, que permitir\u00e1n abordar las variables involucradas tanto exploratoriamente como de manerainferencial. Se utilizar\u00e1 el coeficiente de correlaci\u00f3n lineal de Pearson, el modelo de regresi\u00f3n lineal y se calcular\u00e1el Coeficiente de Cp de Mallows, con un nivel de significaci\u00f3n de 0,05 para todos los casos. Lo cualitativo permitir\u00e1comprender experiencias y perspectivas de los sujetos, la construcci\u00f3n de la teor\u00eda a trav\u00e9s de los hallazgos y lavalidaci\u00f3n mediante el proceso de triangulaci\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2018 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>NIMH - NIH<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26830\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            On Track Chile (OTCH) for First Episode Psychosis\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26830\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26830\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Substantial data support early interventions for people experiencing FEP to ameliorate symptoms and minimize disability. FEP programs have been widely and successfully implemented in high-income countries (HIC). With the partial exception of Chile, however, there is not a single low-and-middle income country (LMIC) that offers universal access to FEP services. Chile is unique among LMICs in having created a platform for the implementation of FEP services, including 1) a FEP policy that mandates identification of FEP individuals at primary care and delivery of community-based FEP treatments at outpatient clinics, and 2) a public health care system within which this mandate can be fulfilled. Nonetheless, our team has documented that FEP services provided at outpatient clinics do not conform to recently established evidence-based approaches. Therefore, the overarching goal of this project is to address the shortfall in evidence-based practices for FEP in Chile by first adapting OnTrackChile (OTCH) from OnTrackNY (OTNY), a coordinated specialty care program for FEP currently being implemented across New York State and the US, and then implementing OTCH on a wide scale. Like most FEP programs, OTNY is clinically effective, but unlike most others, it also has a wellestablished training and technical assistance infrastructure and a proven track record of being scaled up in large urban areas. To achieve our main goal, we will use the Dynamic Adaptation Process model to first inform the adaptation and implementation of OTCH in the Chilean context. We will then use a Hybrid Trial Type 1 design to evaluate the implementation of OTCH, as well as its effectiveness and cost, in a cluster randomized controlled trial (RCT) (N = 300 from 21 outpatient clinics). The cluster-RCT will include the following: blinded interviews with participants (baseline, 12, 24 months); detailed information about service use (every 3 months, needed for cost estimates); assessments of mental health providers (6,12, and 24 months, needed for service and implementation outcomes); and ongoing mixed methods evaluation of the implementation process.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2018 - Diciembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>DAAD - Alemania<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26686\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Labor insertion, working conditions, and health in recently graduated health professionals: A cohort study\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26686\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26686\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]During the last decades, employment conditions has changed in an important way. Although these changes have included more flexible employment relations, it has also included higher levels of job insecurity and lack of social security. This situation has affected all groups of workers, including those in stable jobs(2) and people working in the health sector. Those changes in the labour market have particularly affected young professionals, in this sense, the current rate of youth unemployment is one of the highest reported in recent year, or the conditions in which they work are poor or informal, often working in jobs below their professional training, generating a major concern for the professional future. This situation could generate also additional stress at this stage of life, as well as frustration and demotivation.\r\n\r\nLittle information is available about working conditions and labour insertion process in young health professionals and the association with health conditions. For this, Maria Teresa Solis Soto (Alumna, Bolivia) in coordination with Leonardo Brice\u00f1o (Universidad del Rosario, Colombia), and Ricardo Oyarzun (Universidad Austral de Chile) carried out a study (baseline) to evaluate the relationship between work experiences, expectations and individual characteristics with physical and mental health in newly graduated young professionals.\r\n\r\nThis study, also has the support of Universidade Federal do Paran\u00e1-Brazil, Universidad San Francisco Xavier de Chuquisaca- Bolivia, CIH Alumni Network, and Master in International Occupational Safety and Health. In the universities included, all students in the last year were invited to participate. For baseline study, we collected information about socioeconomic information and, lifestyle, Job expectations, History of previous working conditions, psychosocial factors (pre-employment), academic Information, health conditions.\r\n\r\nThe study ask for ethical approval in each country. International ethical research guidelines were considered at all research steps. A written informed consent form as well as a letter explaining the importance of the study were to the questionnaire. Confidentiality and voluntary participation was respected.\\ Preliminary results were disseminated to inform the local universities. This information will be useful for universities and labour organizations in order to implement strategies that fit with the current and future labour market conditions taking care of the human resource for health.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2018 - Febrero 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>PUCV VICERRECTORIA DE INVESTIGACION<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26965\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Un enfoque integral para entender el desarrollo de \u0093Black spot\u0094 en palta cv. Hass\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26965\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26965\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Chile es uno de los l\u00edderes mundiales en exportaci\u00f3n de fruta de palta, con aumentos de exportaciones cada vez mayores para mercados internacionales durante los \u00faltimos a\u00f1os. A pesar de los crecientes aumentos en las exportaciones de frutos, uno de los problemas en palta es conocido como mancha negra \u0093Black spot\u0094. La mancha negra se evidencia solo despu\u00e9s del almacenamiento postcosecha prolongado, con la aparici\u00f3n de manchas oscuras circulares sobre el exocarpo del fruto y es detectado s\u00f3lo tard\u00edamente en los mercados de exportaci\u00f3n provocando as\u00ed el rechazo de la fruta. El presente proyecto tiene como objetivo entender las causas que originan la aparici\u00f3n de Black spot en frutos de palta var. Hass usando un enfoque integral de metabol\u00f3mica y evaluaciones de calidad poscosecha. Hasta el momento, fueron cosechados frutos de 8 huertos (Ensenada, Pilil\u00e9n, Los Angeles, Resguardo, Inversiones, El Rancho, Quilhuica y Los Lilenes) correspondiente a cosecha temprana y 4 huertos (Resguardo, Pilil\u00e9n, Quilhuica y Los angeles) para cosecha tard\u00eda. Los frutos fueron evaluados a cosecha, a la salida de c\u00e1mara de frio y en madurez de consumo. Los atributos evaluados correspondieron a: peso, color, presencia de da\u00f1o lenticular, da\u00f1o de pulpa, da\u00f1o vascular, firmeza y materia seca. Tambi\u00e9n se hicieron muestreos de epidermis de 5 frutos a la cosecha y cada 10 d\u00edas de almacenamiento (0, 10, 20, 30 y 40 d) para analizar el sistema enzim\u00e1tico  y no-enzim\u00e1tico de defensa y un an\u00e1lisis metab\u00f3lico integral. Los resultados obtenidos hasta la fecha muestran que hay una disminuci\u00f3n de firmeza y peso de frutos almacenados, con disminuci\u00f3n m\u00e1s r\u00e1pida a la salida de c\u00e1mara hasta madurez de consumo. De todos huertos estudiados hasta la fecha no fue observado presencia de Black spot en los diferentes huertos. Muchos frutos estudiados presentaron presencia de lenticelosis, russet en la piel, picoteo y algunos con antracnosis. Frutos de Ensenada, Resguardo y Quilhuica almacenados por 25 d\u00edas en aire regular presentaron alto porcentaje de lenticelosis. Frutos almacenados por 40 d\u00edas presentaron un patr\u00f3n similar, con alto porcentaje de lenticelosis para frutos provenientes del Resguardo, Ensenada y Los Angeles, y presencia de frutos con russet para Resguardo y Pilil\u00e9n. Frutos almacenados por 25 d\u00edas de Ensenada maduraron en promedio en 8 d\u00edas, Los Angeles entre 8 y 10 d\u00edas, Pilil\u00e9n en 10 d\u00edas, Quilhuica y Resguardo en 6 d\u00edas. Cuando los frutos fueron almacenados por 40 d\u00edas, frutos de Ensenada y Pilil\u00e9n maduraron en 5 d\u00edas y aquellos de Los Angeles, Quilhuica y Resguardo maduraron en 3 d\u00edas.  La materia seca de los frutos  de Ensenada (cosecha temprana) y Quilhuica (cosecha tard\u00eda) estuvo por debajo del m\u00ednimo de 23% y 27% respectivamente.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2018 - Mayo 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>The RUFFORD Small Grants<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26484\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Effect of climate change on the growth dynamics of sclerophyllous species of the Chilean Mediterranean forest in a biogeographic gradient\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26484\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26484\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El presente proyecto busca evaluar desde una perspectiva hist\u00f3rica la respuesta de crecimiento y resiliencia ecol\u00f3gica del bosque mediterr\u00e1neo chileno al cambio clim\u00e1tico actual y futuro, utilizando especies de \u00e1rboles escler\u00f3filos en un gradiente altitudinal y latitudinal (32\u00b0-35 \u00b0S), complementando el an\u00e1lisis de anillos de \u00e1rboles y modelos de predicci\u00f3n de distribuci\u00f3n. Compararemos especies con amplia distribuci\u00f3n geogr\u00e1fica (especies no amenazadas) y otras con distribuci\u00f3n restringida (especies amenazadas). Se analizar\u00e1 el crecimiento, el reclutamiento y la idoneidad del h\u00e1bitat en diferentes poblaciones de bosques escler\u00f3filos. Esto nos permitir\u00e1 (i) analizar la capacidad de adaptaci\u00f3n de estos bosques al cambio clim\u00e1tico, y (ii) conocer la predicci\u00f3n de la vulnerabilidad espacial a la mortalidad por sequ\u00eda, lo que podr\u00eda dar lugar a nuevas configuraciones de las distribuciones de los \u00e1rboles escler\u00f3filos.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26862\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Nature of the volcanism and structures of the outer-rise (Chile Central &#8211; Juan Fern\u00e1ndez)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26862\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26862\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Nature of the volcanism and structures of the outer-rise (Chile Central - Juan Fern\u00e1ndez) JFROR[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2018 - Marzo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26007\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            The role of genetic diversity in the success of the parasitoid Mastrus ridens as a biological control agent and in its adaptation to new environments\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26007\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26007\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2018 - Noviembre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Consejo Nacional de las Culturas y las Artes<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26074\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26074\" aria-expanded=\"false\" aria-controls=\"collapse-26074\">\n                                            Cineduka: cine y educaci\u00f3n intercultural en el aula de Ense\u00f1anza B\u00e1sica\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26074\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26074\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto tuvo como objetivos la formaci\u00f3n continua de profesorado de cinco comunas de la regi\u00f3n de O'Higgins en interculturalidad y uso del cine como herramienta de innovaci\u00f3n did\u00e1ctica en el aula de escuelas municipales. \r\nLos beneficiarios directos de Cineduka fueron 11 docentes de Artes Visuales y de Historia y Geograf\u00eda y aproximadamente 700 estudiantes de 7\u00ba a\u00f1o b\u00e1sico de las escuelas participantes.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2018 - Marzo 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26119\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fondecyt Regular 1181341.Time-course modeling of the vascular epigenetic programming by fetal growth restriction: role of endothelial-derived miRNAs on hypoxia- and oxidative stress-induced responses.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26119\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26119\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Adverse intrauterine conditions, such as fetal growth restriction (FGR), increase the risk to develop cardiometabolic diseases in the adulthood. This concept has been called \u0091Developmental Origins of Health and Disease\u0092 (DOHaD) and relies on the activation of mechanisms sensing and signaling a diversity of stimuli during early development that later leads to higher risk of disease. The mechanisms that have been broadly suggested to be involved in these processes are epigenetic modifications in key gene promoters that could \u0091record\u0092 normal and abnormal perinatal stimuli. Intrauterine oxidative stress and chronic hypoxia are common features in FGR. Several cellular processes require the participation of pro-oxidant molecules which are normally neutralized by antioxidant defenses. However, under determined conditions, such as chronic hypoxia, the pro-oxidants overcome these defenses inducing oxidative stress. The latter is an important stimulus that regulates vascular function and cardiovascular physiology, playing a key role in the development of cardiovascular diseases, regulating negatively the bioavailability of the main vasodilator nitric oxide (NO). In addition, the vascular system presents a high phenotypic plasticity during life, which is modulated and restricted by epigenetic mechanisms (including DNA methylation, histone post-translational modifications, and micro RNAs). \r\nThe higher cardiovascular risk in adults born with FGR can be traced back to a reduced arterial compliance in pre-pubertal subjects and a decreased peripheral endothelial-dependent vascular relaxation at birth. This endothelial dysfunction (ED) is also observed in FGR placental vessels, suggesting an early onset of ED that could be evidenced in systemic and placental arteries. Our studies in human placentae have demonstrated that ED in FGR can be modulated by oxidative stress and is associated with changes in proteome profile as well as an epigenetic-mediated regulation of eNOS expression. Similarly, in guinea pigs, we have found that ED in FGR is also occurring in the fetal arteries and is prevented by maternal treatment with antioxidants. Analysis of eNOS expression and Nos3 promoter DNA methylation profile in endothelial cells from the aorta and umbilical arteries of FGR guinea pigs shows common molecular markers of ED in FGR systemic and umbilical vessels which are reverted by a maternal antioxidant treatment. Altogether, these data support the role of oxidative stress in the epigenetic programming of ED in FGR and the potential predictive value of studying human umbilical arteries endothelial cells (HUAEC). However, there are no studies addressing the time course and origins of the ED in FGR and the participation of additional epigenetic mechanisms, such as miRNAs, in this process.    \r\nHere, we put forward two inter-related hypotheses. First, that arterial endothelium from babies with FGR show a genomic DNA methylation signature along with an altered expression of miRNAs miR-21, miR-126 & miR-155, which contributes to changes in the expression of enzymes related to NO synthesis, endothelial dysfunction, and vascular remodeling. Second, that FGR has, during gestation, dynamic changes in the expression of miRNAs miR-21, miR-126 & miR-155 as an early response to hypoxia and oxidative stress in the fetus leading, in the long term, to endothelial dysfunction and vascular remodeling. These hypothesis will be tested in primary cultures of HUAEC from FGR neonates and validated using guinea pig and chick embryo models of FGR according to the following general aims (GA): GA-1 To demonstrate, in human umbilical artery endothelial cells, whether FGR is associated with an altered epigenetic regulation (i.e. increased levels of miR-21, miR-126 & miR-155 and a differential genomic DNA methylation) of NO-related enzymes (i.e. eNOS, DDAH1, Nrf2, Arg2, and HO-1), which modifies the response to hypoxia and impairs angiogenic capacity.GA-2 To demonstrate, in FGR guinea pigs, whether circulating levels of miR-21, miR-126 & miR-155 are dynamically regulated during the development of fetal vascular dysfunction and if the prevention of oxidative stress by an antioxidant administration to mothers, contributes to this regulation. GA-3 To demonstrate, in FGR chicken embryos, whether the silencing of miR-21, miR-126 and miR-155 expression modifies the endothelial and vascular dysfunction induced by chronic hypoxia and oxidative stress. Our expected outcome is to demonstrate that miRNAs miR-21, miR-126 & miR-155 participates in the early defense to hypoxia and oxidative stress in the FGR, but leading at long-term to ED. Further, we propose that regulation of these miRNAs during gestation could prevent these effects. This project is not only relevant to uncover the developmental mechanisms that determine short- and long-term vascular dysfunction, but also to open potential approaches for treatments in complicated pregnancies in humans. Combined, our program of work offers insights into mechanisms underlying the association between intrauterine hypoxia, oxidative stress and the increased risk of developing cardiovascular disease in later life, and possible interventions considering administration of therapeutic agents at critical stages of intrauterine development.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1895<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2018 - Abril 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26164\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Salud mental y resultados acad\u00e9micos en ni\u00f1os del primer ciclo de Ense\u00f1anza B\u00e1sica de la regi\u00f3n de O\u0092Higgins: mejorando logros educacionales en establecimientos municipales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26164\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26164\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La construcci\u00f3n de un modelo predictivo, que podr\u00eda dar origen a una herramienta de screening para ayudar al profesor a identificar un problema de salud mental en el aula y solicitar ayuda a los equipos de apoyo psico-pedag\u00f3gico dentro del establecimiento. De igual forma, este proyecto podr\u00eda dar origen a una cohorte de estudiantes que permita profundizar en el estudio de la relaci\u00f3n salud mental \u0096 resultados acad\u00e9micos, con productos cient\u00edficos (conocimiento) y tecnol\u00f3gicos de innovaci\u00f3n, que apoyen el trabajo de los docentes y sus establecimientos.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2018 - Marzo 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26373\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Evaluaci\u00f3n de la asociaci\u00f3n del tipo de hospedero y de la infecci\u00f3n por Trypanosoma cruzi en Mepraia spinolai\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26373\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26373\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La enfermedad de Chagas es una de las enfermedades parasitarias m\u00e1s importante en Latinoam\u00e9rica, afectando a aproximadamente 6 millones de personas. Esta enfermedad es causada por el protozoo hemoflagelado Trypanosoma cruzi, el cual presenta un ciclo de vida indirecto que incluye insectos hemat\u00f3fagos y mam\u00edferos. Dadas las caracter\u00edsticas de abundancia y asociaci\u00f3n al peridomicilio del vector silvestre Mepraia spinolai, su la amplia distribuci\u00f3n en Chile y las variadas especies de mam\u00edferos que pueden ser identificados como fuente de infecci\u00f3n para este vector, cobra importancia realizar estudios que relacionen a esta especie con sus potenciales hospederos. Del punto de vista epidemiol\u00f3gico, esto es importante para evitar indirectamente la transmisi\u00f3n de T. cruzi al hombre, al disminuir la propagaci\u00f3n de este vector.\r\nObjetivos\r\nPuesto que se elimin\u00f3 al vector Triatoma infestans de los domicilios en Chile, los estudios en los vectores silvestres cobran cada d\u00eda m\u00e1s importancia, sobre todo en \u00e1reas donde se establece el contacto con el hombre. El objetivo principal de esta investigaci\u00f3n es evaluar la interacci\u00f3n entre el tipo de hospedero y la infecci\u00f3n por T. cruzi en M. spinolai, determinando su repercusi\u00f3n en la eficacia biol\u00f3gica de este vector end\u00e9mico.\r\nMetodolog\u00eda\r\nLa evaluaci\u00f3n de la eficacia biol\u00f3gica del vector se realizar\u00e1 a trav\u00e9s de la determinaci\u00f3n de la sobrevivencia poblacional de M. spinolai, de su tiempo de desarrollo hasta estado adulto y de su fecundidad. Esto ser\u00e1 comparado seg\u00fan su dieta espec\u00edfica (conejo, rata, cabra o gallina) y su estatus de infecci\u00f3n por T. cruzi. Cada grupo ser\u00e1 alimentado con un determinado hospedero (sin infecci\u00f3n) a lo largo de toda su vida, desde el estadio II hasta adulto. Los triatominos infectados ser\u00e1n capturados en terreno, y su infecci\u00f3n por T. cruzi ser\u00e1 determinada en deyecciones mediante PCR en tiempo real. Los triatominos no infectados ser\u00e1n obtenidos de una colonia de laboratorio generada a partir de insectos no infectados, libres de infecci\u00f3n. \r\nResultados Esperados\r\nComo resultado general, se podr\u00e1 evaluar la eficacia biol\u00f3gica de esta especie al alimentarse con animales disponibles en el peridomicilio, y se podr\u00e1 discriminar si las diferencias seg\u00fan hospedero var\u00edan en el caso de que los vectores est\u00e9n infectados. Se espera una mayor eficacia biol\u00f3gica por parte del grupo de M. spinolai libres de infecci\u00f3n respecto al grupo de aquellos infectados por T. cruzi. Por otra parte, se espera que el tipo de hospedero del que se alimentan los insectos triatominos tambi\u00e9n genere diferencias en la eficacia biol\u00f3gica del vector, principalmente determinadas por las caracter\u00edsticas sangu\u00edneas de cada especie de vertebrado.\r\nEl conocer qu\u00e9 especie favorece el crecimiento de las poblaciones de M. spinolai, permitir\u00e1 aconsejar sobre medidas de manejo de animales a los pobladores de las regiones end\u00e9micas \u0096 principalmente rurales - que apunten a reducir el riesgo de proliferaci\u00f3n de esta especie en la cercan\u00eda de sus hogares.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1895<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2018 - Abril 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26410\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Salud mental y resultados acad\u00e9micos en ni\u00f1os del primer ciclo de Ense\u00f1anza B\u00e1sica de la regi\u00f3n de O\u0092Higgins: mejorando logros educacionales en establecimientos municipales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26410\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26410\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La construcci\u00f3n de un modelo predictivo, que podr\u00eda dar origen a una herramienta de screening para ayudar al profesor a identificar un problema de salud mental en el aula y solicitar ayuda a los equipos de apoyo psico-pedag\u00f3gico dentro del establecimiento. De igual forma, este proyecto podr\u00eda dar origen a una cohorte de estudiantes que permita profundizar en el estudio de la relaci\u00f3n salud mental \u0096 resultados acad\u00e9micos, con productos cient\u00edficos (conocimiento) y tecnol\u00f3gicos de innovaci\u00f3n, que apoyen el trabajo de los docentes y sus establecimientos.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1895<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2018 - Abril 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26437\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Salud mental y resultados acad\u00e9micos en ni\u00f1os del primer ciclo de Ense\u00f1anza B\u00e1sica de la regi\u00f3n de O\u0092Higgins: mejorando logros educacionales en establecimientos municipales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26437\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26437\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La construcci\u00f3n de un modelo predictivo, que podr\u00eda dar origen a una herramienta de screening para ayudar al profesor a identificar un problema de salud mental en el aula y solicitar ayuda a los equipos de apoyo psico-pedag\u00f3gico dentro del establecimiento. De igual forma, este proyecto podr\u00eda dar origen a una cohorte de estudiantes que permita profundizar en el estudio de la relaci\u00f3n salud mental \u0096 resultados acad\u00e9micos, con productos cient\u00edficos (conocimiento) y tecnol\u00f3gicos de innovaci\u00f3n, que apoyen el trabajo de los docentes y sus establecimientos.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2018 - Octubre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26483\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Dise\u00f1o de plan de rehabilitaci\u00f3n y plan indicativo, incluyendo estudios de severidad del fuego, vulnerabilidad y gravedad del ecosistema \u0093Quebrada del agua\u0094 ante incendios forestales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26483\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26483\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto GEF-Monta\u00f1a\/CONAF[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1895<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2018 - Abril 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26578\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Salud mental y resultados acad\u00e9micos en ni\u00f1os del primer ciclo de Ense\u00f1anza B\u00e1sica de la regi\u00f3n de O\u0092Higgins: mejorando logros educacionales en establecimientos municipales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26578\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26578\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La construcci\u00f3n de un modelo predictivo, que podr\u00eda dar origen a una herramienta de screening para ayudar al profesor a identificar un problema de salud mental en el aula y solicitar ayuda a los equipos de apoyo psico-pedag\u00f3gico dentro del establecimiento. De igual forma, este proyecto podr\u00eda dar origen a una cohorte de estudiantes que permita profundizar en el estudio de la relaci\u00f3n salud mental \u0096 resultados acad\u00e9micos, con productos cient\u00edficos (conocimiento) y tecnol\u00f3gicos de innovaci\u00f3n, que apoyen el trabajo de los docentes y sus establecimientos.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2018 - Noviembre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26600\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desarrollo de una Plataforma Software-as-a-Service para Apoyar Decisiones de Dotaci\u00f3n de Personal en Cadenas de Retail\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26600\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26600\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1895<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2018 - Abril 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26677\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Salud mental y resultados acad\u00e9micos en ni\u00f1os del primer ciclo de Ense\u00f1anza B\u00e1sica de la regi\u00f3n de O\u0092Higgins: mejorando logros educacionales en establecimientos municipales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26677\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26677\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La construcci\u00f3n de un modelo predictivo, que podr\u00eda dar origen a una herramienta de screening para ayudar al profesor a identificar un problema de salud mental en el aula y solicitar ayuda a los equipos de apoyo psico-pedag\u00f3gico dentro del establecimiento. De igual forma, este proyecto podr\u00eda dar origen a una cohorte de estudiantes que permita profundizar en el estudio de la relaci\u00f3n salud mental \u0096 resultados acad\u00e9micos, con productos cient\u00edficos (conocimiento) y tecnol\u00f3gicos de innovaci\u00f3n, que apoyen el trabajo de los docentes y sus establecimientos.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1895<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2018 - Abril 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26831\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Salud mental y resultados acad\u00e9micos en ni\u00f1os del primer ciclo de Ense\u00f1anza B\u00e1sica de la regi\u00f3n de O\u0092Higgins: mejorando logros educacionales en establecimientos municipales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26831\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26831\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La construcci\u00f3n de un modelo predictivo, que podr\u00eda dar origen a una herramienta de screening para ayudar al profesor a identificar un problema de salud mental en el aula y solicitar ayuda a los equipos de apoyo psico-pedag\u00f3gico dentro del establecimiento. De igual forma, este proyecto podr\u00eda dar origen a una cohorte de estudiantes que permita profundizar en el estudio de la relaci\u00f3n salud mental \u0096 resultados acad\u00e9micos, con productos cient\u00edficos (conocimiento) y tecnol\u00f3gicos de innovaci\u00f3n, que apoyen el trabajo de los docentes y sus establecimientos.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2018 - Mayo 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26827\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Evaluaci\u00f3n Pre &#8211; Piloto Programa de Formaci\u00f3n de Cuidadores en ni\u00f1os con trastornos del desarrollo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26827\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26827\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La Organizaci\u00f3n Mundial de la Salud en conjunto con Autism Speaks ha desarrollado el Programa de Formaci\u00f3n a Cuidadores (CST) para ni\u00f1os y ni\u00f1as con TD (OMS, 2018). Dicho proyecto se enmarca en las recomendaciones de la \u0093Gu\u00eda de Intervenci\u00f3n mhGAP para los trastornos mentales, neurol\u00f3gicos y por uso de sustancias de OMS, la cual se implementa desde el a\u00f1o 2016 en la red de Atenci\u00f3n Primaria de Salud de Chile, con un m\u00f3dulo espec\u00edfico de trastornos del desarrollo (OMS, 2010; MINSAL 2018).\r\n\r\nObjetivo general\r\nEvaluar aceptabilidad y factibilidad del pre-piloto CST implementado en la Comuna de Santiago Centro.\r\n\r\nObjetivos espec\u00edficos\r\n1. Analizar las medidas de evaluaci\u00f3n aplicadas a trav\u00e9s de la realizaci\u00f3n del programa.\r\n2. Realizar entrevista a facilitadores y grupo focal a padres, una vez finalizado el programa.\r\n\r\nEstudio cuali-cuantitativo.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> Fondecyt N\u00ba 3180257<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2018 - Marzo 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26854\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Geo-CVOIS: Geomorfolog\u00eda de las Islas Volc\u00e1nicas Oce\u00e1nicas Chilenas y Montes Submarino: Mejorando la comprensi\u00f3n de su origen, evoluci\u00f3n and peligros potenciales.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26854\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26854\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Geomorfolog\u00eda de las Islas Volc\u00e1nicas Oce\u00e1nicas Chilenas y Montes Submarinos: Mejorando la comprensi\u00f3n de su origen, evoluci\u00f3n y peligros potenciales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26727\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            The contribution of the arousal and vigilance systems in the Attention Deficit Hyperactivity Disorder (ADHD): an experimental study (1181472).\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26727\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26727\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]xxxxx[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2018 - Diciembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>sin<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26746\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            El acoso callejero y sus consecuencias psicosociales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26746\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26746\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Materia Espec\u00edfica: Este Proyecto busca analizar el impacto del acoso callejero en mujeres j\u00f3venes en Santiago de Chile de manera experimental[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2018 - Marzo 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26005\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortalecimiento de la Unidad de An\u00e1lisis Biol\u00f3gicos y Qu\u00edmicos de la Universidad de O\u0092Higgins: Cuantificaci\u00f3n de pesticidas en muestras vegetales y humanas de la regi\u00f3n de O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26005\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26005\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2018 - Marzo 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26218\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Xanthomonas arboricola pv. corylina: polyphasic characterization and virulence factors associated with its pathogenicity in European hazelnut in Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26218\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26218\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]xxxx[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2018 - Diciembre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Pontificia Universidad Cat\u00f3lica de Chile<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26235\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Anhedonia en adultos mayores en situaci\u00f3n de abandono. Cambios en la percepci\u00f3n de soluciones dulces en hogares de ancianos.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26235\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26235\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2018 - Diciembre 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26236\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Investigaci\u00f3n en nutrici\u00f3n y conducta alimentaria de cerdo transpac\u00edfico: Fomentando la colaboraci\u00f3n entre la Universidad de Chile, Universidad Cat\u00f3lica y The University of Queensland (Australia).\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26236\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26236\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]PCI. Concurso Redes Fondecyt. REDI170573.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2018 - Diciembre 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26254\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Entendiendo la complejidad metab\u00f3lica y nutricional de frutos en poscosecha: una perspectiva integradora desde la Biolog\u00eda de Sistemas.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26254\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26254\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Redes Internacionales Etapa Inicial PCI 2017-REDESI170422. CONICYT. Proyecto titulado: Entendiendo la complejidad metab\u00f3lica y nutricional de frutos en poscosecha: una perspectiva integradora desde la Biolog\u00eda de Sistemas. Instituci\u00f3n patrocinante: Universidad de Chile y Universidad de O\u0092Higgins. Investigadora responsable Dra. Ang\u00e9lica Reyes. Marzo 2018 \u0096 Diciembre 2019.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2018 - Diciembre 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26255\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estudio de especies bacterianas nativas de importancia nacional mediante estrategias de Biolog\u00eda de Sistemas.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26255\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26255\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Redes Internacionales Etapa Inicial PCI 2017-REDESI170193. CONICYT. Proyecto titulado: Estudio de especies bacterianas nativas de importancia nacional mediante estrategias de Biolog\u00eda de Sistemas. Instituci\u00f3n patrocinante: Universidad de O\u0092Higgins. Marzo 2018 \u0096 Diciembre 2019.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2018 - Diciembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Gobierno Regional - GORE<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26303\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Programa Cordero Saludable\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26303\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26303\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]valorar carne ovina de secano en cuanto a sus propiedades nutriocionales[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2018 - Noviembre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Centro UC Pol\u00edticas P\u00fablicas<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26360\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Juego guiado y educaci\u00f3n parvularia: Propuestas para una mejor calidad de la educaci\u00f3n inicial\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26360\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26360\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto integr\u00f3 a dos estudiantes de la carrera de educaci\u00f3n Parvularia de la Universidad de O'Higgins como asistentes de investigaci\u00f3n: Marcela Meneses y Andrea Saavedra. \r\n\r\nResumen:\r\nExiste hoy consenso en el alto retorno de la inversi\u00f3n en educaci\u00f3n parvularia, especialmente en los\r\nsectores m\u00e1s desaventajados (Banco Mundial, 2011; Lynch, 2004; Heckman, 2006). Este retorno se ve reflejado\r\nen menor gasto social en delincuencia juvenil y en servicios de educaci\u00f3n especial y en mayores ingresos de los\r\nparticipantes de programas de buena calidad. Efectivamente, la evidencia internacional muestra que las estas\r\nintervenciones compensan en alguna medida la influencia de los ambientes de pobreza en el desarrollo de los\r\nni\u00f1os (Campbell, Ramey, Pungello, Sparling, & Miller-Johnson, 2002; Schweinhar, Montie, Xiang, Barnett,\r\nBelfield, & Nores, 2005). Sin embargo, para que sea posible obtener estos efectos es necesaria la provisi\u00f3n de\r\neducaci\u00f3n parvularia de calidad.\r\nUno de los ejes de una educaci\u00f3n parvularia de calidad est\u00e1 dada por el buen uso del juego. A nivel\r\ninternacional, cada vez hay m\u00e1s evidencia de la importancia del juego en el desarrollo del lenguaje, la\r\nmetacognici\u00f3n y la auto-regulaci\u00f3n, predictores centrales del logro acad\u00e9mico posterior y el bienestar socioemocional\r\n(Bornstein, 2006; Whitebread, 2010, 2011; Whitebread et al, 2007). Adem\u00e1s, hay evidencia\r\nespec\u00edfica de que el juego guiado tiene impacto en el aprendizaje de contenidos en \u00e1reas educativas\r\nrelevantes tales como matem\u00e1ticas y lenguaje (Weisberg et al., 2015).\r\nAdem\u00e1s, m\u00faltiple evidencia internacional sugiere que hay una crisis en la educaci\u00f3n parvularia debido\r\na la incorporaci\u00f3n creciente de metas acad\u00e9micas propias de la escuela como una respuesta a las demandas de\r\ndesempe\u00f1o que tiene el sistema educacional (Miller & Almon, 2009). Este mismo fen\u00f3meno est\u00e1 sucediendo\r\nen Chile, observ\u00e1ndose una hiper-escolarizaci\u00f3n de los niveles iniciales (Mineduc, 2016). As\u00ed, el tiempo que los\r\nni\u00f1os dedican a jugar en los jardines infantiles es cada vez m\u00e1s acotado.\r\nLas Bases Curriculares de Educaci\u00f3n Parvularia chilenas relevan el rol del juego dentro de sus\r\nprincipios pedag\u00f3gicos, en donde enfatizan \u0093el car\u00e1cter l\u00fadico que deben tener principalmente las situaciones\r\nde aprendizaje, ya que el juego tiene un sentido fundamental en la vida de la ni\u00f1a y del ni\u00f1o. A trav\u00e9s del\r\njuego, que es b\u00e1sicamente un proceso en s\u00ed para los p\u00e1rvulos y no s\u00f3lo un medio, se abren permanentemente\r\nposibilidades para la imaginaci\u00f3n, lo gozoso, la creatividad y la libertad\u0094 (op. cit., p. 17). Sin embargo, no es lo\r\nque se observa en la sala de p\u00e1rvulos. Un estudio en 12 salas de jard\u00edn infantiles encontr\u00f3 que el tiempo\r\ndedicado al juego era inestructurado y muy limitado: apenas un 4% de la jornada en promedio. Adem\u00e1s de ello, en los jardines de dependencia municipal no se dedicaba en absoluto tiempo al juego (Strasser, Lissi &\r\nSilva, 2009). As\u00ed mismo, un estudio en desarrollo que indaga 60 establecimientos educacionales chilenos,\r\nmuestra que el juego guiado es casi inexistente en las salas de transici\u00f3n mayor, independientemente del nivel\r\nsocio-econ\u00f3mico (Grau et al., 2017). Esto no es coherente con la sabida importancia de la actividad f\u00edsica y de\r\nla participaci\u00f3n activa de los ni\u00f1os sobre su desarrollo y aprendizaje. En efecto, los estudios muestran que la\r\nactividad f\u00edsica de los p\u00e1rvulos mejora la capacidad de atender a un adulto (Holmes, Pellegrini, & Schmidt,\r\n2006) y que el nivel de actividad de los juegos realizados por los p\u00e1rvulos correlaciona con la autorregulaci\u00f3n y\r\naprendizaje durante prekinder (Becker, McClelland, Loprinzi, & Trost, 2014). Incluso existe evidencia de que\r\nsentarse en otras modalidades distintas a las sillas de aulas (por ejemplo en cojines) tiene un impacto positivo\r\nen la atenci\u00f3n e involucramiento de los p\u00e1rvulos (Seifert, & Metz, 2016).\r\nLos hallazgos anteriores subrayan la necesidad de dise\u00f1ar programas que aumenten la cantidad de\r\ntiempo dedicado a actividades adecuadas al nivel de desarrollo cognitivo de los p\u00e1rvulos y reduzcan la\r\nproporci\u00f3n de tiempo improductivo y\/o dedicado a actividades pasivas -como escuchar sentado a la\r\neducadora- o demasiado escolarizadas \u0096tales como completar gu\u00edas en papel. Las intervenciones que buscan\r\nelevar la calidad de las interacciones en el aula de educaci\u00f3n temprana han encontrado resultados mixtos,\r\npero la mayor\u00eda de las intervenciones que han resultado efectivas en el mediano plazo han usado capacitaci\u00f3n\r\nintensiva y acompa\u00f1amiento frecuente (Zaslow, Tout, Halle, Whittaker, Lavelle, 2010). Pero incluso este tipo\r\nde intervenciones costosas en Chile no han mostrado impacto (Yoshikawa et al., 2015), de manera que en\r\nnuestro pa\u00eds no existe a la fecha ning\u00fan modelo de intervenci\u00f3n en centros de educaci\u00f3n parvularia que haya\r\nmostrado efectos en elevar la calidad de las interacciones. Debido a la expansi\u00f3n de la cobertura parvularia en\r\nnuestro pa\u00eds, y al estado de la oferta ya existente, el trabajo hacia la calidad de la formaci\u00f3n de educadores se\r\nvuelve relevante.\r\nAs\u00ed, los desaf\u00edos en la implementaci\u00f3n del juego en las aulas es un problema p\u00fablico impostergable,\r\nque al subsanar avanzamos en brindar cada vez una educaci\u00f3n de mayor calidad para los ni\u00f1os y ni\u00f1as de\r\nnuestro pa\u00eds.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2018 - Febrero 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26361\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Suplemento curricular basado en juegos para el desarrollo del lenguaje, alfabetizaci\u00f3n, conocimiento num\u00e9rico y autoregulaci\u00f3n en niveles medio y transici\u00f3n de educaci\u00f3n parvularia\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26361\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26361\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto integr\u00f3 a cuatro estudiantes de la carrera de Educaci\u00f3n Parvularia de la Universidad de O'Higgins como Asistentes de Investigaci\u00f3n: Sof\u00eda N\u00fa\u00f1ez (cohorte 2018), Fernanda L\u00f3pez (cohorte 2018), Daniela Torres (Cohorte 2017) y Bel\u00e9n Ortega (Cohorte 2017).\r\n\r\nResumen:\r\nLas intervenciones que buscan elevar la calidad de las interacciones en el aula de educaci\u00f3n temprana han encontrado resultados mixtos, pero la mayor\u00eda de las intervenciones que han resultado efectivas en el mediano plazo han usado capacitaci\u00f3n intensiva y acompa\u00f1amiento frecuente (Zaslow, Tout, Halle, Whittaker, Lavelle, 2010). Estas intervenciones son de alto costo. Pero incluso este tipo de intervenciones costosas en Chile no han mostrado impacto (Yoshikawa, Leyva, Snow, Trevi\u00f1o, Barata, Weiland, & ... Arbour, 2015), de manera que en nuestro pa\u00eds no existe a la fecha ning\u00fan modelo de intervenci\u00f3n en centros de educaci\u00f3n parvularia que haya mostrado efectos en elevar la calidad de las interacciones. Debido a la expansi\u00f3n de la cobertura parvularia en nuestro pa\u00eds, y al estado de la oferta ya existente, se requieren soluciones masivas, para las que el costo es un factor determinante.\r\nExisten factores contextuales que podr\u00edan utilizarse para afectar positivamente los procesos de aula. Por ejemplo, un estudio en 19 salas de medio mayor chilenas (Strasser, Darricades, Mendive y Barra, en revisi\u00f3n) mostr\u00f3 que entre 70% y 90% de la varianza en la calidad de las interacciones entre educadoras y p\u00e1rvulos ocurr\u00eda dentro de cada educadora, no entre ellas. Es decir, una misma educadora pod\u00eda producir interacciones muy productivas y otras muy inefectivas en el transcurso del mismo d\u00eda. \u00bfQu\u00e9 explicaba ese 70-90% de varianza en las interacciones de una misma educadora? Los datos sugieren que era el tipo de actividad que estaba realizando. En general, cuando las educadoras estaban realizando una actividad alineada con un aprendizaje esperado de las bases curriculares, ellas tend\u00edan a ser m\u00e1s responsivas, dar m\u00e1s oportunidades de participar a los p\u00e1rvulos, y ser menos directivas, que cuando la actividad no parec\u00eda tener ning\u00fan objetivo de aprendizaje. Esto significa que algunos cambios contextuales \u0096en este caso la actividad que se hace- tienen el potencial de modificar los procesos de sala, sin mediar capacitaciones intensivas a las educadoras. Una actividad que muestra gran potencial para afectar positivamente los procesos de sala es el juego, ya que se ha observado que ciertos contextos de juego generan interacciones de mayor calidad, por ejemplo mayor participaci\u00f3n de los ni\u00f1os en conversaciones (O\u0092Brien & Bi, 1995; Cote, 2001), mayores oportunidades de ejercer la autorregulaci\u00f3n (Bodrova, Germeroth, & Leong, 2013) y menores conductas de estr\u00e9s (Hart, Burts, Durland, Charlesworth, DeWolf & Fleege, 1998). As\u00ed, visualizamos una oportunidad al utilizar el juego para modificar el nivel de las interacciones y la frecuencia de actividades adecuadas al nivel de desarrollo de los p\u00e1rvulos. Hipotetizamos que, si existiera un conjunto de juegos alineados con los aprendizajes esperados de las bases curriculares de la educaci\u00f3n parvularia chilena, ello incrementar\u00eda la cantidad de tiempo que los ni\u00f1os y ni\u00f1as pasan jugando, y con ello, la calidad de las interacciones entre las educadoras y los p\u00e1rvulos.\r\nDe acuerdo a los estudios internacionales (Goble, Hanish, Martin, Eggum-Wilkens, Foster, & Fabes, 2016), se puede predecir que una mejora significativa de la calidad de las interacciones adulto-p\u00e1rvulo en el aula deber\u00eda producir un mejor nivel de desarrollo cognitivo, socioemocional y ling\u00fc\u00edstico en los p\u00e1rvulos. A su vez, estudios longitudinales muestran que los ni\u00f1os y ni\u00f1as que inician la ense\u00f1anza b\u00e1sica con mejores indicadores de desarrollo del lenguaje, la alfabetizaci\u00f3n, las relaciones l\u00f3gico-matem\u00e1ticas y la autoregulaci\u00f3n, tienen mejores resultados educativos de largo plazo (Lynch, Van den Broek, Kremer, Kendeou, White, & Lorch, 2008; Nation & Snowling, 2004; Ouellette, 2006; Sabol, & Pianta, 2012; Verhoeven & Van Leeuwe, 2008). Finalmente, la adici\u00f3n de m\u00e1s tiempo de juego, y espec\u00edficamente, juego adecuado al nivel de desarrollo de los ni\u00f1os y ni\u00f1as, es en s\u00ed misma un objetivo digno de perseguir, dados los hallazgos sobre el impacto positivo que tiene el juego en el bienestar de los ni\u00f1os. Esta soluci\u00f3n tambi\u00e9n aumentar\u00eda el tiempo bruto dedicado al juego, al poner a disposici\u00f3n del personal educativo un repertorio de juegos alineados con las bases curriculares.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2018 - Marzo 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26409\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortalecimiento de la Unidad de An\u00e1lisis Biol\u00f3gicos y Qu\u00edmicos de la Universidad de O\u0092Higgins: Cuantificaci\u00f3n de pesticidas en muestras vegetales y humanas de la regi\u00f3n de O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26409\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26409\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2018 - Diciembre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26452\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desarrollo de un sustrato \u00f3rgano-mineral basado en compost agotado de champi\u00f1\u00f3n, con capacidad de mejorar calidad de suelo para la propagaci\u00f3n y cultivo de plantas ornamentales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26452\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26452\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2018 - Marzo 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26828\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortalecimiento de la Unidad de An\u00e1lisis Biol\u00f3gicos y Qu\u00edmicos de la Universidad de O\u0092Higgins: Cuantificaci\u00f3n de pesticidas en muestras vegetales y humanas de la regi\u00f3n de O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26828\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26828\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2018 - Diciembre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27111\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27111\" aria-expanded=\"false\" aria-controls=\"collapse-27111\">\n                                            Concurso Interno de Investigaci\u00f3n Cient\u00edfica y Tecnol\u00f3gica Regular 2018 de la Universidad de los Lagos: \u0093Identidades profesionales de los artistas-docentes en la regi\u00f3n de Los Lagos. Transformaciones de lo social en compromiso cultural\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27111\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27111\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetivo principal de este estudio es conocer la identidad profesional de los(as) profesores de artes de la regi\u00f3n de Los Lagos y comprender c\u00f3mo \u00e9sta contribuye hacia el desarrollo social y cultural de la region. Para lograr dicho objetivo se proponen cuatro objetivos espec\u00edficos: (1) Identificar qu\u00e9 elementos de la\r\nformaci\u00f3n y trayectoria docente de los(as) profesores de artes son relevantes para construir su identidad\r\nprofesional. (2) Identificar los conflictos, necesidades y las diferencias que experimentan los(as) profesores\r\nde artes en su desarrollo profesional en la regi\u00f3n y analizar c\u00f3mo potenciar dichas tensiones o solventar\r\nesas diferencias. (3) Explorar c\u00f3mo los(as) profesores de artes vinculan sus proyectos art\u00edsticos-educativos\r\ncon las necesidades del entorno regional. (4) Describir las caracter\u00edsticas que componen las pr\u00e1cticas\r\ndocentes y art\u00edsticas de los(as) profesores de artes y analizar c\u00f3mo impactan en el desarrollo social y\r\ncultural de la regi\u00f3n. Este proyecto tendr\u00e1 un dise\u00f1o emergente y utilizar\u00e1 una metodolog\u00eda mixta, que en su primera fase ser\u00e1 cuantitativa y en la segunda cualitativa.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> INFRAIA-02-2017 - Ref: 731070<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Febrero 2018 - Noviembre 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>European Commission<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26855\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26855\" aria-expanded=\"false\" aria-controls=\"collapse-26855\">\n                                            EUROVOLC: \u0093European Network of Observatories and Research Infrastructures for Volcanology\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26855\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26855\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]EUROVOLC will construct an integrated and harmonized European volcanological community able to fully support, exploit and build-upon existing and emerging national and pan-European research infrastructures, including e-Infrastructures of the European Supersite volcanoes. The harmonization includes linking scientists and stakeholders and connecting still isolated volcanological infrastructures located at in situ volcano observatories (VO) and volcanological research institutions (VRIs). EUROVOLC will overcome fragmentation at various levels, including community, project and discipline fragmentation by addressing four main themes: Community building, volcano-atmosphere interaction, sub-surface processes and volcanic crisis preparedness and risk management. Examples of networking activities under these themes include collaboration and networking between VOs, VRIs and civil protection agencies, networking of atmospheric gas and aerosol observations as well as observations of subsurface processes, and initiation of access to multidisciplinary observations from Krafla Volcano Laboratory as a test bed. Joint research activities include production of services to initialize volcanic ash transport and dispersal models during eruptions, integrated modelling of pre-eruption data, and a complete catalogue of European Volcanoes. Trans-national access to European Volcano observatories will be facilitated and virtual access to various modelling and assessment tools for responding to volcanic unrest and eruptions will be offered. Through these activities EUROVOLC will integrate the European volcanological community and open up and provide a wider, simplified, and more efficient access to key, multidisciplinary European research infrastructures located at leading VOs and VRIs to conduct improved volcanological research, drive best practice at volcanological observatories and open pathways for enterprise to better exploit georesources in volcanic areas such as geothermal energy.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2018 - Diciembre 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26726\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            T\u00e9cnicas avanzadas de an\u00e1lisis e interpretaci\u00f3n de datos en etolog\u00eda computerizada.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26726\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26726\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]xxxxxxxxxxx[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2018 - Diciembre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Intramural Research Award Program (IRAP). Touro University California College of Education and Health Sciences.<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26685\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Conocimientos, actitudes y pr\u00e1cticas relacionadas con el c\u00e1ncer cervical en Monteagudo rural, Bolivia.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26685\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26685\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Conocimientos, actitudes y pr\u00e1cticas relacionadas con el c\u00e1ncer cervical en Monteagudo rural, Bolivia.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2018 - Abril 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26177\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Recuperaci\u00f3n de salud de suelos y su implicancia en el restablecimiento de bosque nativo incendiado en zonas del secano de la VI Regi\u00f3n\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26177\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26177\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"].[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2018 - Diciembre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>CONAF<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26178\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            T\u00e9cnicas silviculturales costo-efectivas para reducci\u00f3n de estr\u00e9s h\u00eddrico de plantas en procesos de restauraci\u00f3n de bosque escler\u00f3filo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26178\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26178\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo general\r\n\r\nEvaluar el efecto de t\u00e9cnicas silviculturales sobre el establecimiento de especies del bosque escler\u00f3filo (Kageneckia oblonga, Lithraea caustica, Quillaja saponaria y Schinus polygamus) en sitios degradados y de baja disponibilidad h\u00eddrica.\r\n\r\nObjetivos espec\u00edficos\r\n\r\nComo hip\u00f3tesis de investigaci\u00f3n se plantea que (1) En la fase de establecimiento, plantas producidas en contenedores m\u00e1s largos y con poda lateral debieran presentar mayor volumen radicular y con ello mayor sobrevivencia en campo. Casillas con componentes retenedores de humedad tales como materia org\u00e1nica e hidrogel debieran presentar mayor contenido de humedad de suelo en el periodo estival y as\u00ed mayor sobrevivencia de planta. (2) La aplicaci\u00f3n de riego debiera generar mayor sobrevivencia solamente en plantas provenientes de contenedores m\u00e1s peque\u00f1os plantadas en casillas sin aplicaci\u00f3n de componentes que retengan humedad. La metodolog\u00eda contempla la selecci\u00f3n de un conjunto de especies end\u00e9micas pertenecientes al tipo forestal escler\u00f3filo de inter\u00e9s para la restauraci\u00f3n del bosque escler\u00f3filo. En una primera fase en vivero, se analizar\u00e1n los atributos de calidad de planta y los cambios morfol\u00f3gicos del sistema radical, generados a partir del cultivo en diferentes tipos de contenedor (tama\u00f1o 15x15 cm y 13x20cm) en todas las especies durante una temporada de crecimiento. La segunda fase de campo, contemplar\u00e1 una plantaci\u00f3n experimental que se localizar\u00e1 en una zona rural de la Regi\u00f3n Metropolitana cuyas caracter\u00edsticas son representativas de ambientes con severas limitaciones abi\u00f3ticas para el establecimiento de plantaciones. Se establecer\u00e1n parcelas de 3200 m2 para cada especie por separado. El estudio ser\u00e1 un dise\u00f1o factorial en bloques completos al azar con 16 tratamientos (n=50). Los tratamientos consisten en una combinaci\u00f3n de 2 niveles de tama\u00f1o de contenedor (plantas provenientes de vivero), 4 niveles de casilla de plantaci\u00f3n y 2 niveles de frecuencia de riego. En total se establecer\u00e1n 3200 plantas de las 4 especies. Espec\u00edficamente, se probar\u00e1 el uso de casillas de plantaci\u00f3n profundas (40x80 cm), las cuales variar\u00e1n en el tipo de combinaci\u00f3n de materiales de relleno (control con suelo; mezcla suelo y rocas 3:1; mezcla suelo y materia org\u00e1nica 3:1; mezcla suelo e hidrogel 3:1). Adicionalmente, se aplicar\u00e1n dos frecuencias de riego (riego de subsistencia cada 30 d\u00edas y riego normal cada 7) en primavera y verano por dos temporadas de crecimiento. Se medir\u00e1n los cambios en la humedad de suelo y la tasa de colonizaci\u00f3n de ra\u00edces en la casilla de plantaci\u00f3n. Durante la estaci\u00f3n seca estival (octubre a abril) se medir\u00e1n la tasa de sobrevivencia y crecimiento de todas las especies, as\u00ed como el estado h\u00eddrico de las plantas sometidas a diferentes frecuencias de riego.\r\n\r\nResultados\r\n\r\nDe los resultados de esta investigaci\u00f3n se espera generar importante informaci\u00f3n acerca de alternativas de manejo de plantas en contenedor, as\u00ed como validar la importancia del manejo de la casilla de plantaci\u00f3n mediante el uso de una combinaci\u00f3n de materiales que favorecen la capacidad de retenci\u00f3n de agua y la infiltraci\u00f3n en el suelo para promover el crecimiento de ra\u00edces en profundidad. Esta informaci\u00f3n es relevante en el \u00e1rea de la restauraci\u00f3n ecol\u00f3gica, espec\u00edficamente para la identificaci\u00f3n de criterios de calidad de planta en vivero, selecci\u00f3n de especies para ambientes semi\u00e1ridos, dise\u00f1o y planificaci\u00f3n de plantaciones con \u00e9nfasis en t\u00e9cnicas de conservaci\u00f3n de la humedad en la casilla de plantaci\u00f3n a largo plazo y con m\u00ednimo aporte de riego y la valorizaci\u00f3n de las pr\u00e1cticas potencialmente bonificables por la ley 20.283, que favorezcan la sobrevivencia de las especies en estudio.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2018 - Diciembre 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26284\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desarrollo de un tratamiento biol\u00f3gico avanzado para las aguas residuales de la industria de la celulosa\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26284\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26284\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2018 - Diciembre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26725\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Dimorfismo sexual en aprendizaje: Diferencias sexuales en efectos de inhibici\u00f3n latente, generalizaci\u00f3n, extinci\u00f3n, recuperaci\u00f3n espont\u00e1nea y renovaci\u00f3n, con el procedimiento de aversi\u00f3n condicionada al sabor en ratas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26725\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26725\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2017 - Noviembre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Fundaci\u00f3n para la Innovaci\u00f3n Agraria - FIA<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26220\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Directrices tecnol\u00f3gicas sustentables en fitosanidad para el manejo integrado de enfermedades en la producci\u00f3n de avellana europea de calidad e inocuidad alimentaria exportable, en un contexto de adaptaci\u00f3n al cambio clim\u00e1tico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26220\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26220\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo general\r\nElaborar directrices tecnol\u00f3gicas sustentables en fitosanidad para el Manejo Integrado de enfermedades de pre y pos cosecha en la producci\u00f3n de avellana europea de calidad e inocuidad alimentaria exportable, en un contexto de adaptaci\u00f3n al cambio clim\u00e1tico en la zona centro sur y sur de Chile.\r\n\r\nObjetivos espec\u00edficos\r\nAnalizar informaci\u00f3n en fitosanidad y del manejo de las enfermedades en las plantaciones de avellano europeo vinculadas al proyecto. Determinar prevalencia, impacto econ\u00f3mico y proyecci\u00f3n de las enfermedades bi\u00f3ticas infectivas m\u00e1s significativas en estructuras vegetativas y reproductivas en cvs. Barcelona y Giffoni establecidos en diversas condiciones edafoclim\u00e1ticas (macro-zonas). Identificar morfol\u00f3gica y molecularmente hongos y bacterias fitopat\u00f3genas, y hongos de pos cosecha asociados al avellano europeo cvs. Barcelona y Giffoni en las macro-zonas muestreadas. Evaluar eficacia diferencial en laboratorio y campo de algunos fungicidas y bactericidas comerciales frente a fitopat\u00f3genos prevalentes en avellano europeo, seg\u00fan macro-zonas. Cuantificar infecci\u00f3n f\u00fangica en pos cosecha en semilla de avellana europea recepcionada en planta de secado y acopio. Desarrollar Directrices Tecnol\u00f3gicas Sustentables para el Manejo integrado de enfermedades f\u00fangicas y bacterianas prevalentes en avellano europeo, en un contexto de cambio clim\u00e1tico local seg\u00fan macro-zonas estudiadas. Establecer relaci\u00f3n costo y beneficio atingente al manejo de la(s) enfermedad(es) predominante(s) en tres huertos comerciales de avellano europeo seg\u00fan macro-zonas. Difundir la informaci\u00f3n cient\u00edfico y t\u00e9cnica en fitosanidad generada en el proyecto.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2017 - Diciembre 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26524\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estudio de problemas de Control \u00d3ptimo de procesos de arrastre: Teor\u00eda y Aplicaciones\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26524\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26524\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The goal of this project is to establish an international network between Chile and Italy, in order to study Optimal Control of Sweeping processes.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2017 - Diciembre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26008\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Diplomado en Gesti\u00f3n del Riego y la Nutrici\u00f3n en Sistemas Hortofrut\u00edcolas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26008\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26008\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El desarrollo del sector agr\u00edcola de la Regi\u00f3n de O\u0092Higgins, y el pa\u00eds, presenta enormes desaf\u00edos dada la actual situaci\u00f3n del recurso h\u00eddrico y su proyecci\u00f3n a futuro en relaci\u00f3n al cambio clim\u00e1tico, as\u00ed como el deficiente manejo de los fertilizantes en la agricultura y las mayores restricciones en temas de inocuidad alimentaria.\r\nEl Diplomado en Gesti\u00f3n del Riego y la Nutrici\u00f3n en Sistemas Hortofrut\u00edcolas, se presenta como una herramienta para formar profesionales de la Regi\u00f3n de O\u0092Higgins, u otras, en temas asociados al manejo eficiente y optimizaci\u00f3n en el uso del agua, energ\u00eda y fertilizantes, a trav\u00e9s del dise\u00f1o de sistemas de riego tecnificado. Se dirige a postulantes con grado de licenciado en carreras relacionadas con ciencias agron\u00f3micas, forestales, de la ingenier\u00eda, biol\u00f3gicas, ambientales y\/o qu\u00edmicas. Espec\u00edficamente a profesionales del sector p\u00fablico o privado que se desempe\u00f1en en la producci\u00f3n agr\u00edcola, profesionales del Instituto de Desarrollo Agropecuario (INDAP), Municipalidades, Servicio Agr\u00edcola y Ganadero (SAG), Comisi\u00f3n Nacional de Riego (CNR), acad\u00e9micos de Universidades e Institutos Profesionales, profesionales de empresas privadas, exportadoras, proveedores de insumos y productos, administradores de predios agr\u00edcolas y consultores privados, con deseada experiencia en el uso de sistemas de riego a presi\u00f3n. El Diplomado consta de un total de 157 horas, organizado en jornadas de medio d\u00eda, dos d\u00edas a la semana. La programaci\u00f3n de los contenidos se divide en 11 m\u00f3dulos de aprendizaje en aula, cuatro actividades pr\u00e1cticas en terreno y dos m\u00f3dulos de innovaci\u00f3n. Dentro de las tem\u00e1ticas tratadas est\u00e1n: aspectos fisiol\u00f3gicos de la planta en cuanto a necesidades de riego y nutrici\u00f3n, considerando las relaciones suelo-agua-planta; hidr\u00e1ulica aplicada, dise\u00f1o de riego localizado y fertirrigaci\u00f3n, aspectos legales y elementos de innovaci\u00f3n e investigaci\u00f3n aplicada, entre otros. La metodolog\u00eda de aprendizaje se realizar\u00e1 bajo un ambiente de aprendizaje consciente, bas\u00e1ndose en un sistema de talleres durante cada clase te\u00f3rica, promoviendo el trabajo grupal en base a una situaci\u00f3n de problem\u00e1tica real. El grupo discutir\u00e1, analizar\u00e1, resolver\u00e1 y dise\u00f1ar\u00e1 una soluci\u00f3n innovadora, bajo la tutela orientativa del docente. Adem\u00e1s, los docentes recibir\u00e1n una inducci\u00f3n para trabajar elementos de la innovaci\u00f3n y emprendimiento con los grupos de trabajo, bajo metodolog\u00edas del Design Thinking y Canvas. La evaluaci\u00f3n se har\u00e1 progresivamente, con instancias de retroalimentaci\u00f3n por parte del docente y de los pares, finalizando con el desarrollo de un proyecto abocado a una soluci\u00f3n innovadora real en el uso eficiente de agua, energ\u00eda y fertilizantes, presentado al Comit\u00e9 de Evaluaci\u00f3n. En terreno, los alumnos analizar\u00e1n y propondr\u00e1n ideas y soluciones en los casos observados y tendr\u00e1n la oportunidad de evaluar y operar sistemas de riego tecnificado. Asimismo, a trav\u00e9s de la visita a CEAF podr\u00e1n conocer los avances en investigaci\u00f3n y desarrollo aplicado a la Regi\u00f3n. Con este Diplomado de especializaci\u00f3n se iniciar\u00e1 un proceso de capacitaci\u00f3n t\u00e9cnica continua de profesionales del \u00e1mbito privado y p\u00fablico, cuyo perfil de egreso les permitir\u00e1 contar con las capacidades t\u00e9cnicas pertinentes para una gesti\u00f3n adecuada de los recursos h\u00eddricos. Tema relevante en la Regi\u00f3n, ya que enfrenta un crecimiento importante de superficie para producci\u00f3n agr\u00edcola de exportaci\u00f3n con un recurso h\u00eddrico escaso y finito. La formaci\u00f3n de generaciones de profesionales especialistas una vez insertos en el medio local, utilizaran m\u00e9todos y herramientas que fomenten la innovaci\u00f3n, investigaci\u00f3n y desarrollo, en y para las empresas, difusi\u00f3n y transferencia de tecnolog\u00eda, aceleraci\u00f3n de emprendimiento innovador, fortalecimiento de las redes de apoyo para una mayor competitividad.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2017 - Diciembre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26052\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Red internacional para la identificaci\u00f3n y evaluaci\u00f3n de estrategias de disminuci\u00f3n de la huella de carbono en lecher\u00edas bovinas org\u00e1nicas y convencionales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26052\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26052\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2017 - Marzo 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26307\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Prevalencia y fuentes de exposici\u00f3n a micotoxinas en poblaci\u00f3n de zonas rurales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26307\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26307\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Estimar la exposici\u00f3n a 6 micotoxinas mediante la medici\u00f3n de biomarcadores en orina en una poblaci\u00f3n rural (MAUCO), y asociar el consumo de alimentos a dicha exposici\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2017 - Diciembre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26349\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Diplomado en Gesti\u00f3n del Riego y la Nutrici\u00f3n en Sistemas Hortofrut\u00edcolas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26349\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26349\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El desarrollo del sector agr\u00edcola de la Regi\u00f3n de O\u0092Higgins, y el pa\u00eds, presenta enormes desaf\u00edos dada la actual situaci\u00f3n del recurso h\u00eddrico y su proyecci\u00f3n a futuro en relaci\u00f3n al cambio clim\u00e1tico, as\u00ed como el deficiente manejo de los fertilizantes en la agricultura y las mayores restricciones en temas de inocuidad alimentaria.\r\nEl Diplomado en Gesti\u00f3n del Riego y la Nutrici\u00f3n en Sistemas Hortofrut\u00edcolas, se presenta como una herramienta para formar profesionales de la Regi\u00f3n de O\u0092Higgins, u otras, en temas asociados al manejo eficiente y optimizaci\u00f3n en el uso del agua, energ\u00eda y fertilizantes, a trav\u00e9s del dise\u00f1o de sistemas de riego tecnificado. Se dirige a postulantes con grado de licenciado en carreras relacionadas con ciencias agron\u00f3micas, forestales, de la ingenier\u00eda, biol\u00f3gicas, ambientales y\/o qu\u00edmicas. Espec\u00edficamente a profesionales del sector p\u00fablico o privado que se desempe\u00f1en en la producci\u00f3n agr\u00edcola, profesionales del Instituto de Desarrollo Agropecuario (INDAP), Municipalidades, Servicio Agr\u00edcola y Ganadero (SAG), Comisi\u00f3n Nacional de Riego (CNR), acad\u00e9micos de Universidades e Institutos Profesionales, profesionales de empresas privadas, exportadoras, proveedores de insumos y productos, administradores de predios agr\u00edcolas y consultores privados, con deseada experiencia en el uso de sistemas de riego a presi\u00f3n. El Diplomado consta de un total de 157 horas, organizado en jornadas de medio d\u00eda, dos d\u00edas a la semana. La programaci\u00f3n de los contenidos se divide en 11 m\u00f3dulos de aprendizaje en aula, cuatro actividades pr\u00e1cticas en terreno y dos m\u00f3dulos de innovaci\u00f3n. Dentro de las tem\u00e1ticas tratadas est\u00e1n: aspectos fisiol\u00f3gicos de la planta en cuanto a necesidades de riego y nutrici\u00f3n, considerando las relaciones suelo-agua-planta; hidr\u00e1ulica aplicada, dise\u00f1o de riego localizado y fertirrigaci\u00f3n, aspectos legales y elementos de innovaci\u00f3n e investigaci\u00f3n aplicada, entre otros. La metodolog\u00eda de aprendizaje se realizar\u00e1 bajo un ambiente de aprendizaje consciente, bas\u00e1ndose en un sistema de talleres durante cada clase te\u00f3rica, promoviendo el trabajo grupal en base a una situaci\u00f3n de problem\u00e1tica real. El grupo discutir\u00e1, analizar\u00e1, resolver\u00e1 y dise\u00f1ar\u00e1 una soluci\u00f3n innovadora, bajo la tutela orientativa del docente. Adem\u00e1s, los docentes recibir\u00e1n una inducci\u00f3n para trabajar elementos de la innovaci\u00f3n y emprendimiento con los grupos de trabajo, bajo metodolog\u00edas del Design Thinking y Canvas. La evaluaci\u00f3n se har\u00e1 progresivamente, con instancias de retroalimentaci\u00f3n por parte del docente y de los pares, finalizando con el desarrollo de un proyecto abocado a una soluci\u00f3n innovadora real en el uso eficiente de agua, energ\u00eda y fertilizantes, presentado al Comit\u00e9 de Evaluaci\u00f3n. En terreno, los alumnos analizar\u00e1n y propondr\u00e1n ideas y soluciones en los casos observados y tendr\u00e1n la oportunidad de evaluar y operar sistemas de riego tecnificado. Asimismo, a trav\u00e9s de la visita a CEAF podr\u00e1n conocer los avances en investigaci\u00f3n y desarrollo aplicado a la Regi\u00f3n. Con este Diplomado de especializaci\u00f3n se iniciar\u00e1 un proceso de capacitaci\u00f3n t\u00e9cnica continua de profesionales del \u00e1mbito privado y p\u00fablico, cuyo perfil de egreso les permitir\u00e1 contar con las capacidades t\u00e9cnicas pertinentes para una gesti\u00f3n adecuada de los recursos h\u00eddricos. Tema relevante en la Regi\u00f3n, ya que enfrenta un crecimiento importante de superficie para producci\u00f3n agr\u00edcola de exportaci\u00f3n con un recurso h\u00eddrico escaso y finito. La formaci\u00f3n de generaciones de profesionales especialistas una vez insertos en el medio local, utilizaran m\u00e9todos y herramientas que fomenten la innovaci\u00f3n, investigaci\u00f3n y desarrollo, en y para las empresas, difusi\u00f3n y transferencia de tecnolog\u00eda, aceleraci\u00f3n de emprendimiento innovador, fortalecimiento de las redes de apoyo para una mayor competitividad.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2017 - Octubre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26678\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Building a Consortium: Planning Research to Improve Accessibility to Mental Health Services for Vulnerable Populations in Latin America.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26678\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26678\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Latin America is home to an estimated 600 million people, the majority of whom live in severe economic deprivation and political instability. While mental illness and substance use problems (MISUP) in Latin America account for approximately a tenth of the world's total burden of the disease, very few individuals receive adequate treatment. 18 million Latin Americans are reported to be facing unemployment, eviction, and homelessness as a result of mental disorders. Untreated MISUP are a major public health issue as they can lead to long-term disability, impaired functioning, caregiver burden, and ultimately premature death. Given the prevalence of such issues in Latin America, an effort to address health equity and accessibility to mental health services is warranted. Research regarding mental health service use in Latin America is scarce, with even fewer studies focusing on barriers to accessibility such as stigma and discrimination. The goal for this project is to share key insights among Latin American countries to better understand factors that inhibit access to mental health services. Funding for a 3-day meeting bringing together key stakeholders from Chile, Canada, Peru, Bolivia and Argentina who are actively addressing these issues will serve three objectives: 1. Dissemination of Research - Disseminating findings from anti-stigma projects in Chile, Peru and Canada detailing challenges within their health systems, impact of interventions and opportunities to further research in this area. 2. Information Gathering - Exploring research studies concerning factors that prevent access to mental health care in Bolivia and Argentina to extract key insights from each approach. 3. Collaboration - Developing new, relevant and collaborative regional projects, research and interventions addressing accessibility to mental health services.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2017 - Octubre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26833\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Building a Consortium: Planning Research to Improve Accessibility to Mental Health Services for Vulnerable Populations in Latin America.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26833\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26833\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Latin America is home to an estimated 600 million people, the majority of whom live in severe economic deprivation and political instability. While mental illness and substance use problems (MISUP) in Latin America account for approximately a tenth of the world's total burden of the disease, very few individuals receive adequate treatment. 18 million Latin Americans are reported to be facing unemployment, eviction, and homelessness as a result of mental disorders. Untreated MISUP are a major public health issue as they can lead to long-term disability, impaired functioning, caregiver burden, and ultimately premature death. Given the prevalence of such issues in Latin America, an effort to address health equity and accessibility to mental health services is warranted. Research regarding mental health service use in Latin America is scarce, with even fewer studies focusing on barriers to accessibility such as stigma and discrimination. The goal for this project is to share key insights among Latin American countries to better understand factors that inhibit access to mental health services. Funding for a 3-day meeting bringing together key stakeholders from Chile, Canada, Peru, Bolivia and Argentina who are actively addressing these issues will serve three objectives: 1. Dissemination of Research - Disseminating findings from anti-stigma projects in Chile, Peru and Canada detailing challenges within their health systems, impact of interventions and opportunities to further research in this area. 2. Information Gathering - Exploring research studies concerning factors that prevent access to mental health care in Bolivia and Argentina to extract key insights from each approach. 3. Collaboration - Developing new, relevant and collaborative regional projects, research and interventions addressing accessibility to mental health services.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> URO1795<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26009\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortalecimiento de la Unidad de An\u00e1lisis Biol\u00f3gicos y Qu\u00edmicos de la Universidad de O\u0092Higgins: Cuantificaci\u00f3n de pesticidas en muestras vegetales y humanas de la regi\u00f3n de O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26009\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26009\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo General: \r\nEvaluar la presencia de pesticidas en tejidos vegetales y su potencial transferencia por ingesta de alimentos a j\u00f3venes que habitan en la regi\u00f3n de O'Higgins[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> URO1795<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26180\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortalecimiento de la Unidad de An\u00e1lisis Biol\u00f3gicos y Qu\u00edmicos de la Universidad de O\u0092Higgins: Cuantificaci\u00f3n de pesticidas en muestras vegetales y humanas de la regi\u00f3n de O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26180\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26180\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo General: \r\nEvaluar la presencia de pesticidas en tejidos vegetales y su potencial transferencia por ingesta de alimentos a j\u00f3venes que habitan en la regi\u00f3n de O'Higgins[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> URO1795<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26221\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortalecimiento de la Unidad de An\u00e1lisis Biol\u00f3gicos y Qu\u00edmicos de la Universidad de O\u0092Higgins: Cuantificaci\u00f3n de pesticidas en muestras vegetales y humanas de la regi\u00f3n de O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26221\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26221\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo General: \r\nEvaluar la presencia de pesticidas en tejidos vegetales y su potencial transferencia por ingesta de alimentos a j\u00f3venes que habitan en la regi\u00f3n de O'Higgins[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> URO1795<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26285\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortalecimiento de la Unidad de An\u00e1lisis Biol\u00f3gicos y Qu\u00edmicos de la Universidad de O\u0092Higgins: Cuantificaci\u00f3n de pesticidas en muestras vegetales y humanas de la regi\u00f3n de O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26285\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26285\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo General: \r\nEvaluar la presencia de pesticidas en tejidos vegetales y su potencial transferencia por ingesta de alimentos a j\u00f3venes que habitan en la regi\u00f3n de O'Higgins[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> URO1795<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26305\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortalecimiento de la Unidad de An\u00e1lisis Biol\u00f3gicos y Qu\u00edmicos de la Universidad de O\u0092Higgins: Cuantificaci\u00f3n de pesticidas en muestras vegetales y humanas de la regi\u00f3n de O&#8217;Higgins\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26305\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26305\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo General: \r\nEvaluar la presencia de pesticidas en tejidos vegetales y su potencial transferencia por ingesta de alimentos a j\u00f3venes que habitan en la regi\u00f3n de O'Higgins[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2017 - Octubre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Natinoal Research Foundation of Korea<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26905\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Environmental Organic Carbon Forensics Laboratory\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26905\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26905\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Centro de investigaci\u00f3n para el estudio de loas fuentes de la din\u00e1mica del carbono org\u00e1nico en los ecosistemas acu\u00e1ticos naturales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2017 - Octubre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26789\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Voces desde dentro: experiencias con escritura acad\u00e9mica de estudiantes del Programa PACE en tres universidades chilenas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26789\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26789\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El programa PACE representa una de las pol\u00edticas m\u00e1s importantes y masivas de apertura del acceso universitario en el pa\u00eds. Debido a que es una pol\u00edtica reciente, se conoce muy poco sobre las competencias y pr\u00e1cticas letradas acad\u00e9micas de los estudiantes y sobre las estrategias institucionales de preparaci\u00f3n y acompa\u00f1amiento para este u otros grupos similares.\r\n\r\nEl presente proyecto busca aportar datos emp\u00edricos acerca del desempe\u00f1o y desarrollo como escritores de estos estudiantes en los primeros a\u00f1os de su trayectoria universitaria en tres universidades con perfiles institucionales diferentes. Por un lado, se espera elaborar una descripci\u00f3n exhaustiva de su perfil de escritores desde una perspectiva de reivindicaci\u00f3n de sus conocimientos, pr\u00e1cticas y experiencias previas. Por otro, se busca contribuir al mejoramiento de la pol\u00edtica p\u00fablica por medio de la identificaci\u00f3n de las necesidades, las instancias de apoyo formales e informales que experimentan y el desarrollo de su escritura acad\u00e9mica una vez dentro de la universidad.\r\n\r\nPara el logro de este prop\u00f3sito i) se describir\u00e1n las pr\u00e1cticas y conocimientos letrados previos, tanto acad\u00e9micos como vern\u00e1culos de estudiantes del Programa PACE, ii) se describir\u00e1n las trayectorias de formaci\u00f3n en escritura acad\u00e9mica de estudiantes del Programa PACE de diferentes universidades chilenas, desde su ingreso a la educaci\u00f3n superior hasta mediados del segundo a\u00f1o y iii) se identificar\u00e1n las oportunidades, los logros y las dificultades de ense\u00f1anza y aprendizaje de la escritura acad\u00e9mica. Los resultados de estas tres dimensiones se comparar\u00e1n 3 en tres universidades del CRUCH con tres perfiles distintos que han implementado el Programa PACE.\r\n\r\nEl estudio se organiza en tres fases de recogida de datos con diferentes instrumentos: cuestionario web a funcionarios PACE; entrevistas inicial y de seguimiento; encuestas; y fuentes textuales (materiales de los cursos y textos escritos por los estudiantes). Estos datos son analizados con codificaci\u00f3n abierta emergente y triangulados. Adem\u00e1s, se construyen historias de literacidad.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2017 - Noviembre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25978\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Identificaci\u00f3n, ponderaci\u00f3n y validaci\u00f3n en terreno de factores predictivos para el \u00e9xito de tratamientos antiparasitarios por inmersi\u00f3n por medio de un panel de expertos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25978\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25978\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26032\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Oportunidades de aprendizaje en matem\u00e1ticas para estudiantes con discapacidad intelectual en escuelas especiales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26032\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26032\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2017 - Septiembre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26120\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Development of in ovo model for treating the hypoxia-induced fetal growth restriction in the chicken embryo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26120\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26120\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]As a scientist in Chile, I have been focused on understanding the mechanisms underlying fetal vascular dysfunction associated with altered fetal growth with a special interest in impaired fetal growth and epigenetic regulation.   Fetal growth restriction (FGR), commonly defined by a weight below the 10th percentile is associated with increased perinatal morbidity and mortality with an incidence of 3 to 10% of all live births1, 2. Therefore, FGR remains at the forefront of basic science and clinical investigation, as it poses a significant problem on every nation\u0092s wealth and health.  Adverse conditions in complicated pregnancy known to induce FGR include reductions in fetal oxygenation or chronic fetal hypoxia3.  Several studies in humans have established that high altitude pregnancy reduces fetal growth 4-6.  Further, several studies in mammalian animal models of hypoxic pregnancy have also reported a significant effect in slowing fetal growth7. However, since most high altitude populations are also impoverished with a high prevalence of maternal undernutrition and since hypoxic exposure of mammalian animals during pregnancy can reduce maternal food intake7, the partial contributions of fetal under-nutrition versus fetal under-oxygenation in promoting FGR remain uncertain.  \r\nThe Giussani group at the University of Cambridge have combined the chick embryo model with hypoxic incubation to isolate the direct effects of chronic fetal hypoxia in promoting FGR.  This group has shown that incubation at high altitude of fertilized eggs laid by sea level hens leads to FGR.  Conversely, incubation at sea level of fertilized eggs laid by high altitude hens that normally show FGR completely recovered fetal growth.  Importantly, incubation at high altitude of fertilized eggs laid by sea level with oxygen supplementation also prevented FGR8.  Recent studies by the Cambridge group have also reported that isobaric rather than hypobaric chronic fetal hypoxia also leads to FGR in the chick embryo9.  Further, they have reported that FGR as a result of isolated chronic fetal hypoxia is associated with significant oxidative stress and endothelial dysfunction in fetal peripheral circulations. Treatment of chick embryos during hypoxic incubation with the antioxidant melatonin rescued the endothelial dysfunction in peripheral circulations by the end of the incubation period. The mechanisms involved included reduced oxidative stress, enhanced antioxidant capacity, restored vascular endothelial growth factor expression and increased NO bioavailability9.  Combined, therefore, studies by the Cambridge group have isolated a direct effect of hypoxia in promoting FGR and fetal endothelial dysfunction independent of effects at the level of the placenta or the mother and suggest that antioxidant therapy may also have a direct protective effect on the fetus.\r\nThese findings are of particular interest to me because my research group in Chile has recently established a guinea pig experimental model of FGR.  This is by progressive bilateral occlusion of the uterine arteries during the second half of gestation that gradually increases placental vascular resistance10, 11. Using this guinea pig model, we have recently shown that FGR induces epigenetic programming of eNOS expression in the fetal endothelium, which is prevented by a maternal treatment with N-acetylcysteine11. However, whether the effects of increased placental vascular resistance on the fetal epigenetic programming of eNOS expression is due to fetal under-nutrition versus fetal under-oxygenation in this model of FGR again remains uncertain.  Therefore, the aim of my research proposal is to use the Cambridge chick embryo model of FGR as a result of hypoxic incubation to isolate the direct effects of chronic fetal hypoxia on epigenetic regulation promoting fetal vascular dysfunction.  This would be the first step to enable better identification of potential targets for clinical intervention designed to protect the developing fetal circulation in pregnancy complicated by FGR and chronic fetal hypoxia.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2017 - Diciembre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26834\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desarrollo de instrumentos culturalmente espec\u00edficos sobre estigma hacia la enfermedad mental y su relaci\u00f3n con funcionalidad global en Am\u00e9rica Latina (Development of Specific Cultural Elements to Evaluate Stigmas towards Mental Health and its Relationshi\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26834\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26834\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]*Research Question(s)\/Hypothesis (es)\r\nAim 1: To examine the degree to which 'what matters most' differs in Chile and Argentina from other cultures in which this has been studied by qualitatively assessing key culture-specific domains of stigma. We propose that thematic analyses will reveal differences in how \u0091what matters most\u0092 shapes stigma in these contexts.\r\nAim 2: To operationalize items to create \u0091culture-specific\u0092 stigma modules for two widely used stigma measures. We will operationalize culture-specific variation in stigma via a pool of initial survey items and use pilot testing with local experts and respondents to create final \u0091culture specific\u0092 stigma modules for each scale.\r\nAim 3: To validate 2 new measures of \u0091culture-specific\u0092 and \u0091universal\u0092 aspects of stigma by administering these measures to 150 participants in Chile. We propose that our \u0091culture-specific\u0092 modules will aid prediction of construct validity scales, with different domains of global functioning as key outcomes.\r\n*Study Implementation\r\nWe are carrying out our fieldwork to develop culturally specific assessments of stigma in two sites: the city of Cordoba in Argentina and in the Santiago Metropolitan area and the adjacent Region of O\u0092Higgins in Chile.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 2017 SGR 1254<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Septiembre 2017 - Julio 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>AGAUR<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27112\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27112\" aria-expanded=\"false\" aria-controls=\"collapse-27112\">\n                                            Investigadora Internacional Investigaci\u00f3n I+D Projecte visual Duoda. Imatges de llibertat femenina. Biblioteca Virtual d\u0092Investigaci\u00f3 i Doc\u00e8ncia Duoda.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27112\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27112\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Los objetivos del proyecto fueron ampliaci\u00f3n del archivo del sistema de imagenes de la cultura visual de las mujeres[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2017 - Diciembre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26832\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Atenci\u00f3n Primaria y Salud Mental: Estudio multic\u00e9ntrico de Redes de Servicios de Salud Mental en Per\u00fa, Argentina, Bolivia, Ecuador y Chile  (EVAREDCOM)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26832\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26832\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La Becas Iberoamericana, J\u00f3venes Profesores e Investigadores de Santander Universidades permiti\u00f3 iniciar y desarrollar una l\u00ednea de investigaci\u00f3n que aun mantengo vinculada a la evaluaci\u00f3n de servicios de salud mental comunitaria.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FON170009<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2017 - Octubre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26165\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Est\u00e1ndares t\u00e9cnicos para el diagn\u00f3stico inicial de los futuros docentes: \u0093Una propuesta basada en evidencia\u0094. Cargo: Co-Investigadora\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26165\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26165\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]FONIDE 2017 (proyecto n\u00ba FON170009)[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2017 - Julio 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26525\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            From monotonicity to dynamic and equilibrium; structures and applications\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26525\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26525\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto de colaboraci\u00f3n internacional entre Chile, Per\u00fa, Brasil y Chile.\r\n\r\nC\u00f3digo proyecto: 17-MATH-06[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FON170009<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2017 - Octubre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26579\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Est\u00e1ndares t\u00e9cnicos para el diagn\u00f3stico inicial de los futuros docentes: \u0093Una propuesta basada en evidencia\u0094. Cargo: Co-Investigadora\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26579\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26579\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]FONIDE 2017 (proyecto n\u00ba FON170009)[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2017 - Junio 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26123\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Time-course modeling of the endothelial epigenetic programming by fetal growth restriction: role of miRNAs miR-21 &#038; miR-126.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26123\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26123\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Corporaci\u00f3n de Fomento de la Producci\u00f3n - CORFO<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26219\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Centro para la Investigaci\u00f3n e Innovaci\u00f3n en Fruticultura para La Zona Sur\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26219\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26219\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Resumen Programa\r\nEl Centro para la Investigaci\u00f3n e Innovaci\u00f3n en Fruticultura para la Zona Sur busca hacer un uso coordinado de las capacidades tecnol\u00f3gicas instaladas en distintas instituciones de investigaci\u00f3n del pa\u00eds para enfrentar los desaf\u00edos tecnol\u00f3gicos de la fruticultura chilena, aprovechando las oportunidades que el mercado mundial ofrece al sector productor y exportador. Esta iniciativa busca reforzar las capacidades existentes para realizar investigaci\u00f3n, desarrollo e innovaci\u00f3n de manera de mejorar la competitividad del sector frut\u00edcola chileno, particularmente en los rubros de avellano, cerezo y nogal para enfrentar los desaf\u00edos del sector con una mirada trans-institucional e interdisciplinaria, con miras al a\u00f1o 2030. El programa aborda los aspectos de sostenibilidad y uso eficiente de recursos en las 3 especies se\u00f1aladas, los aspectos gen\u00e9ticos de la producci\u00f3n frutal y los aspectos de postcosecha y calidad de la fruta fresca.\r\n\r\nObjetivo general\r\nIncrementar la I+D+i frut\u00edcola en Chile, mediante la ejecuci\u00f3n articulada de portafolios de proyectos con visi\u00f3n de largo plazo, que permitan acortar las brechas en tres \u00e1mbitos espec\u00edficos del desarrollo frut\u00edcola para mejorar la productividad del sector y contribuir a diversificar y sofisticar el tejido productivo.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2017 - Mayo 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Fundaci\u00f3n Nacional de Investigaci\u00f3n de Corea<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26900\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desarrollo de una metodolog\u00eda basada en los biomarcadores lip\u00eddicos para identificar las fuentes de la materia org\u00e1nica en sedimentos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26900\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26900\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetiv\u00f3 del proyecto de investigaci\u00f3n era el desarrollo de una caja de trazadores de la materia\r\norg\u00e1nica para entender la din\u00e1mica de la materia org\u00e1nica (MO), los procesos biogeoqu\u00edmicos y el\r\npapel de esta materia en el ciclo del carbono a la escala local y regional. Para lograr este objetiv\u00f3, la\r\nidentificaci\u00f3n precisa de la fuente de MO es un elemento esencial. La utilizaci\u00f3n de varios\r\nbiomarcadores moleculares y especialmente el uso de biomarcadores de l\u00edpidos, debido a su presencia\r\nubicua y estabilidad diagen\u00e9ticos y qu\u00edmica, representan uno de los enfoques con un gran potencial.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2017 - Octubre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26256\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            EUROPEAN COMMISSION REA: MILEAGE N\u00ba734931.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26256\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26256\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto Internacional EUROPEAN COMMISSION\u0096REA: MILEAGE N\u00ba734931. Proyecto titulado: Microelements in Life Expectancy and Aging. Instituciones patrocinantes: University of Aberdeen (Inglaterra), Universidad de Chile y Universidad de O\u0092Higgins. Director Dr. John Beattie. Mayo 2017 \u0096 Abril 2021.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2017 - Enero 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26835\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desarrollo y evaluaci\u00f3n de un modelo de intervenci\u00f3n basado en tecnolog\u00edas de la informaci\u00f3n y de la comunicaci\u00f3n (TICs) para reducir el riesgo de suicidio adolescente en establecimientos educacionales de la RM y la VI Regi\u00f3n.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26835\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26835\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivo General del proyecto fue desarrollar y evaluar un modelo de intervenci\u00f3n basado en tecnolog\u00edas de la informaci\u00f3n y comunicaci\u00f3n para reducir riesgo suicida y fortalecer factores protectores de la salud mental en adolescentes de establecimientos educacionales de la RM y VI Regi\u00f3n.\r\nEl producto central es una plataforma web, con aplicaciones m\u00f3viles asociadas, que incluye un componente psicoeducativo y uno interactivo que estar\u00e1 constituido por recursos que fomentan el apoyo entre pares (adolescentes) y la generaci\u00f3n de estrategias para afrontar problemas afectivos y sociales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2017 - Marzo 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26121\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fondecyt Regular 1170608. Biomechanical behavior of arteries from chronic hypoxic animals: experiments, modelling, numerical simulation and validation\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26121\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26121\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Appropriate arterial function and structure are vital for a proper cardiovascular performance and therefore fundamental for a healthy life. Arterial function depends on cellular and molecular mechanisms but as well on the structural features. In fact, it has been shown that structural and biomechanical properties of vessels are very much related to several cardiovascular pathologies, such as systemic and pulmonary hypertension. Chronic lack of oxygen (hypoxia), may determine an impairment of the cardiovascular function, potentially deriving in pulmonary\/systemic hypertension and cardiac failure. This is particularly relevant in human populations exposed to high altitude (above 2500m), either in chronic continuous (permanent inhabitants) or chronic intermittent (shifts of high altitude workers, such as miners, custom agents astronomers; and mountaineers) fashions. Most of the studies about vascular effects of chronic hypoxia have focused on function and molecular mechanisms involved in the pathophysiological responses. However, few is known about the biomechanical responses of systemic, pulmonary and cerebral arteries in these conditions, particularly in the chronic exposure to hypoxia as it happens in high-altitude population and in several diseases in lowlanders. The main goal of this project is to determine the vascular biomechanical characteristics of a representative rat paradigm of living under hypoxia and, in addition, establish the modelling, numerical simulation and experimental validation of the biomechanical responses of arterial vessels.\r\nSpecifically, three different types of vessels (aorta, carotid and femoral), at different age (neonates, juveniles and adults)\r\nwill be analyzed, either under normoxic, chronic permanent hypoxic or chronic intermittent hypoxic conditions.\r\nSmall rodents have been extensively used as a paradigm of cardiovascular and vascular function, allowing massive\r\nsteps in the knowledge of mechanisms involved in cardiovascular pathologies. Using a rat model, we will deeply analyze\r\nthe biomechanical properties of the vasculature of animals exposed to chronic hypoxia (permanent or intermittent) in a\r\nhypobaric chamber, adding substantial data for the comprehension of the vascular biomechanical behaviour under these\r\nconditions.\r\nThe need for a better understanding of the biomechanical response of arteries leads to the development of constitutive\r\nmodels that may define realistic and reliable stress-strain relationships. In this project, several constitutive models aimed\r\nat describing the biomechanical behaviour of soft tissues will be assessed. The specific aspects to be taken into account\r\nof the vessels biomechanical characterisation are: incompressibility of the tissue, presence of large deformations, isotropic and anisotropic material behaviours, residual stresses, rate dependent (i.e., viscous) effects, damage and active response. The material characterisation of the biomechanical behaviour of rat arteries will be performed via in-vitro biaxial and myograph tensile tests and ring opening test, considering standard, cyclic and relaxation loading conditions. From these experiments, the material characterisation will also involve the derivation of the material parameters. Specifically, we will address the development of algorithms for the treatment of non-linearities in the fitting procedure and sensitivity analysis to determine the consistency of the parameters found with this methodology. The analysis will also include comparison between the numerical predictions of the different constitutive models in their application to experimental data to be measured in this project.\r\nThe analysis of the response of pressurised straight arterial vessels will be additionally carried out. Importantly, this\r\ntest mimics the in-vivo physiological conditions of the arterial vessel. Aside from the internal pressure, axial stretching is\r\nusually considered. As a non-uniform biaxial stress state is commonly developed in this test, this fact extends the validity of the material characterisation. The material response will be described via the constitutive models previously characterised. Due to the complex stress and strain patterns developed in this problem, numerical simulations defined in the context of the finite element method will be performed. The obtained numerical results will be validated with the corresponding experimental measurements. Moreover, we expect to characterise the biomechanical properties of different vascular beds, representatives of systemic, pulmonary and cerebral circulations. We shall also describe the effects of chronic hypoxia on these properties. Furthermore, we will perform histological analyses to assess the ultrastructure and the wall components of the intima, media and adventitia layers and relate them with the biomechanical findings.\r\nThe outcomes of this project will enhance the knowledge necessary to integrate the functional, structural and\r\nbiomechanical properties of vascular tissues. Clearly, our data will provide useful information not only for vascular pathophysiology understanding, but also for optimization of medical diagnosis, prognosis and potential therapeutic approaches to the related pathologies[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2017 - Marzo 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26122\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fondecyt Regular 1171406. Fetal programming of inflammatory responses and body fat by maternal obesity: Role of DHA in the modulation of epigenetic markers of obesity and metabolic disease\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26122\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26122\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Overweight and Obesity are worldwide epidemic conditions defined as a body mass index (BMI) &#8805; 25 and &#8805;30, respectively, characterized by an excessive accumulation of adipose tissue in the body that impairs both physical and psychosocial health and well-being [1]. Notably, according to the Chilean National Health Survey (ENS 2009-2010), 60% of woman in reproductive age (i.e. 15 and 44 years) are overweight or obese [2] with detrimental consequences on women as well as offspring health at long term. Epidemiological evidences have recognized pre-gestational obesity and, in a lesser degree, excessive gestational weight gain (GWG) as independent risk factors in the development of maternal complications and adverse perinatal outcomes [3]. This includes congenital malformations, perinatal death, large for gestational age babies (LGA, >p 90th), macrosomia (> 4 Kg at birth), birth dystocia, neonatal hypoglycemia, and others [4]. This evidences leaded the Institute of Medicine of the National Academy of Sciences of the United States (IOM) to provide guidelines for maternal weight gain in 1990, updated in 2009 [5] in order to improve maternal and perinatal outcomes. Conversely, a large number of evidence has shown that a deficient maternal nutrition during pregnancy affects the early in utero development, inducing adaptations\/responses in the fetus and neonate which have been associated to increased risk of diseases in adulthood [6]. This concept, known as \"Developmental Origins of Health and Disease\u0094 (DOHaD, referred also as intrauterine programming in this proposal) which was coined by Professor David Barker, who reported the association of low birth weight and the risk of T2DM and cardiovascular disease. Notably not only in utero under-nutrition (e.g. intrauterine growth restriction) but also over-nutrition (e.g. macrosomia, LGA) increase the cardiometabolic risk in the offspring [7-9]. Whilst the effect of maternal undernutrition on the risk of disease in the offspring has been extensively addressed, new efforts are required to clarify how increased maternal obesity and body fat previous and during pregnancy impinge an increased cardiometabolic risk in the progeny.\r\n   In this context, in addition to perinatal complications associated with maternal obesity (MO), there is evidence of persistent adverse effects in the offspring throughout their lifespan. In fact, excessive maternal gestational weight gain is associated with a 2-fold increase in cardiometabolic risk in the offspring, which is evidenced since early infancy [10]. Notably, this effect is substantially higher (~5-fold increase) in offspring from women that initiate their pregnancy with obesity [11, 12]. This is relevant due to the high rate of childhood overweight\/obesity in Chile (32.2% of the children &#8804; 6 yo are overweight\/obese, according to the ENS 2010), which is a strong predictor of later cardiometabolic complications in adulthood [13]. The effect of MO on susceptibility to obesity in the offspring appears to be independent of the presence of gestational diabetes (GDM) [14, 15]. This could have its origin during fetal development since it has been described that newborn whose mothers are obese, with normal glycaemia during gestation, present an increased adiposity versus lean mass compared to control pregnancies [16]. In this respect, it is noteworthy that the size of abdominal adipose tissue and hepatocellular lipid content in neonates strongly correlates with maternal BMI [17-19]. This has been also observed in offspring from pregnant obese non-human primates and mice, which exhibit increased accumulation of hepatic triglycerides and ceramides even before birth [17-19]. Furthermore, MO also relates with metabolic disturbances in the newborn, such as a reduced insulin sensitivity and altered inflammatory markers [20]. Altogether these data suggest that postnatal obesity could be programmed by MO during fetal development, however the mechanisms underlying the intrauterine programming of obesity are currently unknown. In this context inflammation, a mechanism exacerbated in pregnancies with MO, represents a potential pathway participating in this process.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 3170706<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2017 - Marzo 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26509\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fondecyt de postdoctorado 3170706. Uso de modelos de distribuci\u00f3n para caracterizar la biodiversidad de megafauna extinta e identificar rutas de migraci\u00f3n de cazadores recolectores en Sudam\u00e9rica.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26509\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26509\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Objetivos: \r\nCaso de estudio continental\r\n1)\tCaracterizar y reconocer las \u00e1reas de mayor biodiversidad de megafauna extinta (mam\u00edferos de >44 kg de masa corporal) para el periodo de transici\u00f3n Pleistoceno-Holoceno en Sudam\u00e9rica. \r\n2)\tIdentificar si dichas \u00e1reas corresponden a posibles corredores o rutas utilizadas por los primeros cazadores-recolectores que colonizaron el continente durante el Pleistoceno tard\u00edo.\r\nCaso de estudio particular: Desierto de Atacama \r\n3)\tCaracterizar la distribuci\u00f3n de especies de megafauna para para el Desierto de Atacama (y para los Andes Centrales), tomando en cuenta el rico registro paleoclim\u00e1tico de la regi\u00f3n como variable explicativa de la presencia de ciertas especies de megafauna en este sector.\r\n4)\tAnalizar si dicha distribuci\u00f3n podr\u00eda explicar el uso por parte de los primeros humanos de distintas rutas de migraci\u00f3n en el sector (costeras, alto andinas y a trav\u00e9s del desierto). \r\n\r\nMetodolog\u00eda: \r\nGenerar Modelos de Distribuci\u00f3n de Especies a nivel continental para los distintos taxa de megafauna extinta sudamericana que existieron durante la transici\u00f3n Pleistoceno-Holoceno. Estos modelos se generar\u00e1n utilizando la locaci\u00f3n geogr\u00e1fica e informaci\u00f3n cronol\u00f3gica del rico registro f\u00f3sil de megafauna existente para Sudam\u00e9rica, junto con informaci\u00f3n de las condiciones ambientales extra\u00edda de modelos clim\u00e1ticos generados para distintos momentos de la transici\u00f3n Pleistoceno-Holoceno. A partir de los Modelos de Distribuci\u00f3n de Especies se identificar\u00e1n las \u00e1reas de mayor biodiversidad (aquellas con la mayor cantidad de taxa) las cuales se comprar\u00e1n con la distribuci\u00f3n geogr\u00e1fica de sitios arqueol\u00f3gicos tempranos. Todo esto con la finalidad de identificar posibles rutas de migraci\u00f3n humana hacia el continente. \r\nPara el caso del Desierto de Atacama (y de los Andes centrales) se aplicar\u00e1 la misma metodolog\u00eda descrita anteriormente pero haciendo uso del rico registro paleclim\u00e1tico existente para la regi\u00f3n. Adem\u00e1s, utilizar\u00e9 los modelos para estimar la distribuci\u00f3n pasada de especies actuales que habitan el sector desde el Pleistoceno tard\u00edo. Los Modelos de Distribuci\u00f3n de Especies resultantes se compraran con la distribuci\u00f3n geogr\u00e1fica de sitios arqueol\u00f3gicos para intentar reconocer las rutas migratorias usadas por los primeros humanos que colonizaban este ambiente extremo. Con la idea de obtener mayor informaci\u00f3n acerca de la megafauna extinta que habit\u00f3 el Desierto de Atacama, me unir\u00e9 a un grupo de investigadores en labores de rescate y an\u00e1lisis de sitios f\u00f3siles recientemente encontrados. Mi prop\u00f3sito es aportar con mi conocimiento de dataci\u00f3n de megafauna extinta por radiocarbono y obtener m\u00e1s datos que mejoren la calidad de los modelos planeados.\r\n\r\nResultados esperados:\r\nSe espera que la superposici\u00f3n de los modelos de distribuci\u00f3n de megafauna extinta para la transici\u00f3n Pleistoceno-Holoceno muestre las \u00e1reas que probablemente exhib\u00edan la mayor biodiversidad para este periodo. Al comprar dichas \u00e1reas con la locaci\u00f3n geogr\u00e1fica de los sitios tempranos de colonizaci\u00f3n humana en Sudam\u00e9rica, se espera reconocer si las rutas de migraci\u00f3n escogidas por los primeros cazadores-recolectores habr\u00edan sido determinadas por la presencia de mayor o menor biodiversidad de megafauna. \r\nPara el caso del Desierto de Atacama y los Andes Centrales, se espera obtener la probable distribuci\u00f3n de las especies de megafauna que habitaban el \u00e1rea de manera m\u00e1s detallada, dado el uso de registros paleoclim\u00e1ticos espec\u00edficos para la zona como variables predictivas. \r\nSe espera que dichos Modelos de Distribuci\u00f3n de Especies de megafauna permitan comprender e identificar la elecci\u00f3n de rutas migratorias por los primeros cazadores-recolectores que habitaron estas regiones en particular.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 3170601<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2017 - Marzo 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26043\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Socializaci\u00f3n y participaci\u00f3n. La vida en colectividad de ni\u00f1os y ni\u00f1as de tres a\u00f1os de edad en la Educaci\u00f3n Inicial Chilena\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26043\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26043\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto tuvo por objetivo principal, identificar y analizar los rasgos de una \u0093vida colectiva\u0094 de ni\u00f1os y ni\u00f1as de tres a\u00f1os de edad en distintas estructuras de educaci\u00f3n parvularia en Chile. Lo anterior, prestado atenci\u00f3n tanto a los componentes estructurales como a las din\u00e1micas de socializaci\u00f3n y participaci\u00f3n que supone esta experiencia.\r\nObjetivos espec\u00edficos:\r\n- Describir y analizar la estructuraci\u00f3n espacio-temporal predominante en cada estructura analizada, en el entendido que su organizaci\u00f3n diferenciada posibilita distintos tipos de experiencias para los ni\u00f1os.\r\n- Identificar y analizar las modalidades de participaci\u00f3n de ni\u00f1os\/as en distintos tipos de actividades o espacios de pr\u00e1cticas (pedag\u00f3gicas, recreativas, de cuidado, etc.).\r\n- Identificar y describir las modalidades y contenidos de las interacciones de los ni\u00f1os, tanto entre pares como con adultos.\r\n- Identificar y analizar los discursos y representaciones que desde los adultos (padres y equipos pedag\u00f3gicos) contribuyen a la configuraci\u00f3n de esta vida en colectividad.\r\n- Analizar las perspectivas de los propios ni\u00f1os respecto de su experiencia colectiva, co-construyendo junto a ellos los significados que le asocian.\r\n- Comparar distintas experiencias de socializaci\u00f3n en y entre diferentes unidades educativas, proponiendo pistas interpretativas respecto de las posibilidades de aprendizaje \u0093informal\u0094 que conllevan.\r\n\r\nMetodolog\u00eda: Utilizamos un esquema de estudio de casos aplicado a tres unidades educativas diferentes: un jard\u00edn infantil p\u00fablico gratuito, un jard\u00edn infantil privado ubicado en un sector de \u0093clase media\u0094, y un grupo \"play group\" inserto en una instituci\u00f3n educativa privada extendida (colegio). Orientadas a p\u00fablicos distintos, funcionando con diferentes niveles de recursos, supusimos la existencia de experiencias de socializaci\u00f3n diferenciables en estas unidades educativas.\r\nLa investigaci\u00f3n recurri\u00f3 a la utilizaci\u00f3n de un enfoque cualitativo y comparativo, contrastando las voces y miradas de los distintos actores implicados en el proceso educativo. Recurrimos al an\u00e1lisis cruzado de datos obtenidos a partir de la aplicaci\u00f3n de diferentes t\u00e9cnicas, entre las que destacan: observaciones (toma de notas y filmaci\u00f3n) de seis jornadas completas en cada una de las estructuras consideradas, \u0093siguiendo\u0094 cada vez a un ni\u00f1o\/a en particular; elaboraci\u00f3n de montajes audiovisuales a partir del material recolectado; realizaci\u00f3n de entrevistas tanto con padres como con equipos pedag\u00f3gicos, utilizando como soporte para la conversaci\u00f3n los mencionados montajes; y la aplicaci\u00f3n de dispositivos orientados a co-construir el \u0093punto de vista infantil\u0094 respecto de esta experiencia de vida en colectividad (\"walk and talk\" y toma de fotograf\u00edas por parte de los mismos ni\u00f1os)[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2017 - Marzo 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26453\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Improving the agricultural waste composting by the addition of nanoclays and biochar: Reduction of gas emissions and nutrient losses in a grassland model system.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26453\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26453\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> Fondecyt Postdoctorado 3170040<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2017 - Octubre 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26472\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Control Predictivo Robusto y Estoc\u00e1stico: Acercando Teor\u00eda y Aplicaciones\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26472\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26472\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Esta investigaci\u00f3n busca dise\u00f1ar estrategias de Control Predictivo Robusto y Control Predictivo Estoc\u00e1stico que reduzcan la distancia entre la teor\u00eda y la pr\u00e1ctica, en particular habilitando el uso de parametrizaciones complejas en los problemas de control \u00f3ptimo, mediante una reducci\u00f3n en la carga computacional, y eliminando el conservatismo en la imposici\u00f3n de restricciones probabil\u00edsticas, para as\u00ed mejorar el desempe\u00f1o de los sistemas de control en sistemas reales, tales como sistemas de climatizaci\u00f3n, micro-redes y ruteo de veh\u00edculos el\u00e9ctricos[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> CONICYT\/FONDECYT\/3170740<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2017 - Marzo 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27122\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27122\" aria-expanded=\"false\" aria-controls=\"collapse-27122\">\n                                            La integraci\u00f3n del territorio puesta a prueba: justicia espacial en el desarrollo de zonas aisladas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27122\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27122\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Antecedentes\r\nEl aislamiento geogr\u00e1fico suele abordarse desde una mirada negativa, que lo plantea como una dificultad aun antes de reconocer las especificidades y potencialidades que esta condici\u00f3n implica. Se trata de territorios en los que podemos encontrar culturas \u00fanicas, o ambientes pr\u00edstinos que han sido poco intervenidos, o representar un atractivo precisamente por otorgar experiencias de paz y tranquilidad inexistentes en zonas altamente conectadas. Sin embargo, los esfuerzos de integraci\u00f3n territorial suelen enfatizar la homogeneizaci\u00f3n de las condiciones de vida mediante infraestructura vial, servicios y localizaci\u00f3n de actividades productivas. Chile ha sido ejemplo de esto. Su geograf\u00eda compleja est\u00e1 caracterizada por zonas rezagadas del crecimiento econ\u00f3mico que se experimenta en las zonas centrales. De ah\u00ed la intenci\u00f3n de promover su difusi\u00f3n hacia estos territorios. Sin embargo, este proceso no siempre responde a las expectativas de quienes los habitan. Esto, porque la integraci\u00f3n al resto del pa\u00eds suele ser decidida con criterios centralizados o que no ponderan adecuadamente las especificidades de estos sectores.\r\n\r\nLa experiencia chilena de integraci\u00f3n a la econom\u00eda mundial ha intensificado este escenario a riesgo de exacerbar las desigualdades territoriales y sociales. En principio, esto no es parte del problema, en tanto que las especificidades apuntan precisamente a destacar la heterogeneidad. S\u00ed lo es, en cambio, que estas desigualdades est\u00e1n acompa\u00f1adas de inequidades que afectan el ejercicio de derechos a quienes residen en zonas aisladas. La apertura econ\u00f3mica ha estado acompa\u00f1ada de desregulaci\u00f3n a nivel local, clave para facilitar la incorporaci\u00f3n a cadenas de valor transnacionales. No obstante, la labor correctiva es d\u00e9bil en los mercados. As\u00ed, la integraci\u00f3n territorial a trav\u00e9s de la econom\u00eda resulta en una imposici\u00f3n de criterios de desarrollo que no se condicen necesariamente con las expectativas de los habitantes en condiciones de aislamiento.\r\n\r\nLa complejidad de este fen\u00f3meno es mayor al tomar en consideraci\u00f3n que el estatismo tampoco representa una soluci\u00f3n, especialmente en casos en que en los territorios aislados hay un componente identitario fuerte o una pretensi\u00f3n auton\u00f3mica articulada. La noci\u00f3n de justicia espacial abre un debate sobre el reconocimiento de derechos territoriales en dos niveles: la de sujetos portadores de derechos y la de Estados garantes de derechos. En esta discusi\u00f3n juegan un rol las definiciones sobre democracia e institucionalidad pol\u00edtica, expectativas a nivel local y los paradigmas y criterios de decisi\u00f3n con injerencia territorial por parte de actores ligados al aparato estatal centralizado. Por ello el planteamiento es que el enfoque de integraci\u00f3n territorial es puesto a prueba al confrontar el desarrollo de zonas aisladas con criterios de justicia espacial.\r\n\r\nProblema de investigaci\u00f3n\r\nEl principal objetivo de este proyecto es comprender las expectativas de desarrollo existentes en las zonas aisladas de Chile. Para ello se utilizar\u00e1 un dise\u00f1o cualitativo para reconocer las nociones de desarrollo existentes en las zonas aisladas, las estructuras de decisi\u00f3n con injerencia territorial, los mecanismos de incorporaci\u00f3n o rechazo de nociones espec\u00edficas de desarrollo.\r\n\r\nTambi\u00e9n se elaborar\u00e1 una trayectoria del aislamiento en tres comunas como casos de estudio, que corresponden a tres formas diferenciadas de aislamiento. Por una parte, Isla de Pascua constituye un caso de aislamiento acompa\u00f1ado por una demanda auton\u00f3mica claramente articulada a partir de una identidad \u00e9tnica. Ays\u00e9n representa un ejemplo de aislamiento valorado positivamente por sus habitantes, especialmente los de la zona costera, obligando a una distinci\u00f3n entre conectividad y dotaci\u00f3n de servicios en el esfuerzo integrador. Cabo de Hornos muestra a una comuna que depende fuertemente de la presencia militar, siendo gravitante en su cotidianeidad el ejercicio de soberan\u00eda nacional.\r\n\r\nResultados\r\n\r\nUn debate sobre las especificidades del aislamiento en Chile, con \u00e9nfasis en la generaci\u00f3n de conocimiento para la toma de decisiones p\u00fablicas, la elaboraci\u00f3n de conceptos y teor\u00eda a partir de los casos de estudio, principalmente en t\u00e9rminos de la epistemolog\u00eda del desarrollo territorial, en la distinci\u00f3n de mecanismos de integraci\u00f3n y diferenciaci\u00f3n socioespacial y en la formulaci\u00f3n de criterios de equidad en el tratamiento de zonas aisladas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2017 - Diciembre 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25976\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            CaligusLIFE: Investigaci\u00f3n cient\u00edfica de excelencia para la comprensi\u00f3n de la biolog\u00eda de Caligus rogercresseyi y su aplicaci\u00f3n en estrategias de control de la Caligidosis en la industria del salm\u00f3n\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25976\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25976\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2017 - Febrero 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25977\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Epidemiolog\u00eda de la co-infecci\u00f3n de Caligus rogercresseyi y Piscirickettsia salmonis en salm\u00f3nidos de cultivo en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25977\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25977\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26031\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Metodolog\u00edas innovadoras para la formaci\u00f3n inicial de profesores de educaci\u00f3n b\u00e1sica en matem\u00e1tica: modelo basado en pr\u00e1cticas efectivas de aula y tecnolog\u00edas de la informaci\u00f3n\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26031\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26031\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Fondef ID16I10119. \r\nInvestigadora responsable Salom\u00e9 Mart\u00ednez, CMM, Universidad de Chile.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> ID16I10090<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2017 - Marzo 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26166\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Habilidades y Competencias para la Educaci\u00f3n Superior. Desarrollo de Instrumentos y Propuestas que aporten a un Nuevo Sistema de Admisi\u00f3n\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26166\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26166\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]FONDEF 2016 (proyecto n\u00ba ID16I10090)[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2017 - Diciembre 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26257\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Synergistic transcriptional response of Listeria monocytogenes to low temperature and copper.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26257\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26257\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Fondecyt Regular 2017-N\u00b01171575. CONICYT. Proyecto titulado: Synergistic transcriptional response of Listeria monocytogenes to low temperature and copper. Instituciones patrocinantes: Universidad de Chile y Universidad de O\u0092Higgins. Investigadora responsable Dra. Ang\u00e9lica Reyes. Marzo 2017-Diciembre 2019.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2017 - Febrero 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26322\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Atmospheric Rivers in the Southeastern Pacific and Their Impact on Extreme Orographic Precipitation\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26322\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26322\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26580\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Pensamiento matem\u00e1tico creativo en aulas de ense\u00f1anza b\u00e1sica de la Regi\u00f3n Metropolitana: entornos did\u00e1cticos que posibilitan su desarrollo.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26580\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26580\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2017 - Febrero 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26747\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            OWNERS: \u0091This country is ours\u0092: Collective psychological OWNERShip and ethnic attitudes [European Research Council Grant]\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26747\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26747\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Materia Espec\u00edfica: OWNERS es un proyecto de investigaci\u00f3n de 5 a\u00f1os (2017-2022) financiado por una Beca de Iniciaci\u00f3n del Consejo Europeo de Investigaci\u00f3n (ERC) otorgada al Dr. Borja Martinovi&#263; en la Universidad de Utrecht, Pa\u00edses Bajos. El proyecto examina la propiedad psicol\u00f3gica colectiva (CPO), la sensaci\u00f3n de que un territorio pertenece al grupo \u00e9tnico de uno. Declaraciones como 'nosotros estuvimos aqu\u00ed primero' o 'construimos este pa\u00eds' son cada vez m\u00e1s utilizadas por los pol\u00edticos de derecha en los pa\u00edses de inmigraci\u00f3n para reclamar la propiedad sobre una base hist\u00f3rica del grupo \u00e9tnico dominante y para excluir a los reci\u00e9n llegados, y tambi\u00e9n hay contextos en los que dos los grupos establecidos no est\u00e1n de acuerdo sobre la propiedad territorial, como los Mapuche en Chile, y los albaneses y los serbios en Kosovo, entre otros.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2017 - Diciembre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Superintendencia de Seguridad Social (Concursos SUSESO)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26838\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            La salud mental como factor de riesgo para los accidentes del trabajo y el ausentismo laboral: un estudio de cohorte\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26838\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26838\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Nuestro proyecto, espera dos grandes aportes.\r\nUn primer resultado de este proyecto corresponde al mejor conocimiento acerca de la interrelaci\u00f3n que existe entre los problemas de salud mental y otras condiciones que afectan la salud de los trabajadores, como es el caso de los accidentes. Y lo mismo se puede se\u00f1alar respecto del mejor conocimiento de los factores que inciden en el ausentismo, y por tanto en las consecuencias que este puede tener para los trabajadores y para las empresas.\r\nUn segundo resultado se refiere al desarrollo de instrumentos para la identificaci\u00f3n de este tipo de problemas en los trabajadores. Uno de los primeros pasos para el desarrollo de intervenciones es contar con encuestas y\/o escalas (instrumentos psicom\u00e9tricos) que sean eficientes en la identificaci\u00f3n de estos s\u00edntomas mentales, lo m\u00e1s breve posibles, focalizada en aquellos s\u00edntomas m\u00e1s relevantes y adaptada para la realidad de nuestro pa\u00eds, y en especial para ser aplicada a trabajadores dentro de nuestras ambientes laborales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Febrero 2017 - Enero 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26788\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Autoevaluarse para aprender: efecto de la elaboraci\u00f3n cooperativa de r\u00fabricas en las capacidades escritas y orales de estudiantes de primer a\u00f1o de Pedagog\u00eda en Educaci\u00f3n Media en Biolog\u00eda y Qu\u00edmica\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26788\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26788\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El poster cient\u00edfico es uno de los g\u00e9neros discursivos multimodales m\u00e1s comunes y efectivos de comunicaci\u00f3n entre pares en las reuniones cient\u00edficas: ofrece grandes ventajas pedag\u00f3gicas que exceden los contenidos disciplinares ya que presenta una actividad compleja que exige al estudiante una alta compenetraci\u00f3n con el tema, capacidad de s\u00edntesis y coherencia entre los lenguajes escrito, oral y las im\u00e1genes que utilizar\u00e1 como apoyo. Todos estos aspectos hacen que tambi\u00e9n sea un g\u00e9nero de formaci\u00f3n acad\u00e9mica que sirve como herramienta de ense\u00f1anza y aprendizaje. A su vez, las pautas de cotejo dise\u00f1adas en forma conjunta entre el docente y los estudiantes aumentan la comprensi\u00f3n de cada evento considerado en la evaluaci\u00f3n y permiten construir una idea anticipada de la actividad que ser\u00e1 evaluada.\r\n\r\nPor este potencial, se propone llevar las r\u00fabricas de evaluaci\u00f3n de las producciones escritas y orales al trabajo en el aula en el marco de la revisi\u00f3n bibliogr\u00e1fica que los estudiantes del curso de Biolog\u00eda Celular para Profesores de Educaci\u00f3n Media deben presentar de manera que estas r\u00fabricas de evaluaci\u00f3n que no se restrinjan a evaluar un producto terminado, sino que acompa\u00f1en y apuntalen el proceso de escritura.\r\n\r\nDurante el a\u00f1o 2017 se incorporar\u00e1 un taller en el que los estudiantes participar\u00e1n en la elaboraci\u00f3n de las r\u00fabricas de evaluaci\u00f3n de los paneles. Esta actividad permitir\u00e1 a los estudiantes definir claramente los conceptos y par\u00e1metros que les ser\u00e1n exigidos y redundar\u00e1 en mejoras significativas en el lenguaje, el uso de citas, la coherencia del texto con las im\u00e1genes utilizadas y la presentaci\u00f3n oral, elementos que ser\u00e1n evaluados por los acad\u00e9micos. Como control sin tratamiento se aprovechar\u00e1n los paneles y las r\u00fabricas de las cohortes de estudiantes 2015 y 2016, donde se cuantificar\u00e1n y clasificar\u00e1n los errores ling\u00fc\u00edsticos, correlacion\u00e1ndolos con los elementos especificados en las r\u00fabricas utilizadas hasta ahora y que fueron definidas por el equipo docente del curso.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2017 - Noviembre 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26306\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Prevalencia y fuentes de exposici\u00f3n a aflatoxina en una poblaci\u00f3n de alto riesgo de c\u00e1nceres de ves\u00edcula biliar y de est\u00f3mago\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26306\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26306\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Estimar la exposici\u00f3n aflatoxina mediante la medici\u00f3n de aflatoxina M1 en la orina de participantes de la Cohorte del Maule, y asociar el consumo de alimentos a dicha exposici\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> MICINN CGL2017-84901-C2-1-P<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Estatal de Investigaci\u00f3n (Espa\u00f1a)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26863\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            SIMPROP (MODEM): Radiografiando sistemas magm\u00e1ticos SIl\u00edcicos: el Magmatismo Permo-carbon\u00edfeRO del Pirineo Catal\u00e1n\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26863\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26863\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La conexi\u00f3n plut\u00f3nico-volc\u00e1nica se ha postulado principalmente en base a enfoques petrol\u00f3gicos, geoqu\u00edmicos, geocronol\u00f3gicos, y geof\u00edsicos, y modelos te\u00f3ricos, todos ellos proporcionando evidencia indirecta, aunque de momento se han ofrecido muy pocos ejemplos de campo de dicha conexi\u00f3n. La raz\u00f3n es que la mayor\u00eda de los terrenos volc\u00e1nicos bien expuestos son demasiado j\u00f3venes para que la erosi\u00f3n o la tect\u00f3nica hayan exhumado sus ra\u00edces plut\u00f3nicas m\u00e1s profundas, mientras que los terrenos plut\u00f3nicos son demasiado viejos para preservar los posibles equivalentes volc\u00e1nicos. El volcanismo del P\u00e9rmico Superior-Carbon\u00edfero-Inferior del Pirineo catal\u00e1n ofrece una excepci\u00f3n a esta regla general, y expone varias rocas plut\u00f3nicas, subvolc\u00e1nicas y volc\u00e1nicas contempor\u00e1neas y cogen\u00e9ticas, ofreciendo as\u00ed un buen ejemplo de campo de la existencia de dicha conexi\u00f3n plut\u00f3nico-volc\u00e1nica. La reconstrucci\u00f3n estratigr\u00e1fica y estructural basada de este complejo plut\u00f3nico-subvolc\u00e1nico-volc\u00e1nico, as\u00ed como las nuevas edades radiom\u00e9tricas U-Th en circones, demuestran que hubo una relaci\u00f3n tiempo-espacio entre todos ellos, ofreciendo as\u00ed uno de las pocas evidencias directas de la existencia de la conexi\u00f3n plut\u00f3nico-volc\u00e1nica[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Estatal de Investigaci\u00f3n (AEI) de Espa\u00f1a<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26973\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Pensamiento funcional en estudiantes de Educaci\u00f3n Primaria como aproximaci\u00f3n al pensamiento algebraico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26973\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26973\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]www.pensamientoalgebraico.es[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2017 - Enero 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26042\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            El juego dentro y fuera del aula: miradas cruzadas sobre pr\u00e1cticas l\u00fadicas infantiles en momentos de transici\u00f3n educativa\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26042\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26042\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La investigaci\u00f3n explor\u00f3 las perspectivas de ni\u00f1os y ni\u00f1as chilenos de entre 4 y 8 a\u00f1os acerca de las pr\u00e1cticas l\u00fadicas desarrolladas en contexto educativo, contrastando sus opiniones con las de padres y educadoras\/es.\r\nParte importante de la investigaci\u00f3n actual en materia de juego, educaci\u00f3n y aprendizaje en la primera infancia, se ha enfocado en la comprensi\u00f3n de los mecanismos de aprendizaje que podr\u00edan verse facilitados o potenciados por el juego. Sin embargo, el estudio de las perspectivas de los propios actores acerca de sus procesos de aprendizaje ha sido considerado de manera menos intensiva y m\u00e1s reciente. Escuchar las perspectivas de los ni\u00f1os respecto del juego puede contribuir a un mejor dise\u00f1o de pol\u00edticas y de pr\u00e1cticas pedag\u00f3gicas en el campo de la educaci\u00f3n y del cuidado en la primera infancia.\r\nEl dise\u00f1o de la investigaci\u00f3n fue cualitativo y exploratorio, incorporando metodolog\u00edas que incluyen observaciones de campo, videograbaci\u00f3n y entrevistas semiestructuradas individuales y grupales con ni\u00f1os y adultos. Se trabaj\u00f3 con cuatro escuelas de diferentes contextos socioecon\u00f3micos y culturales, abordando a un total de 35 ni\u00f1os (16 ni\u00f1as y 19 ni\u00f1os). Se solicit\u00f3 el consentimiento informado de todos los adultos implicados y el asentimiento de todos los ni\u00f1os participantes, buscando resguardar en todo momento tanto su anonimato como su bienestar y participaci\u00f3n voluntaria.\r\nLa investigaci\u00f3n busc\u00f3 traer a la discusi\u00f3n las perspectivas de ni\u00f1os y ni\u00f1as acerca de sus oportunidades de juego y aprendizaje en momentos de transici\u00f3n educativa, contribuyendo a la reflexi\u00f3n acerca del rol del juego en las pr\u00e1cticas pedag\u00f3gicas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2017 - Enero 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26362\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            El juego dentro y fuera del aula: miradas cruzadas sobre pr\u00e1cticas l\u00fadicas infantiles en momentos de transici\u00f3n educativa\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26362\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26362\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La investigaci\u00f3n explor\u00f3 las perspectivas de ni\u00f1os y ni\u00f1as chilenos de entre 4 y 8 a\u00f1os acerca de las pr\u00e1cticas l\u00fadicas desarrolladas en contexto educativo, contrastando sus opiniones con las de padres y educadoras\/es.\r\nParte importante de la investigaci\u00f3n actual en materia de juego, educaci\u00f3n y aprendizaje en la primera infancia, se ha enfocado en la comprensi\u00f3n de los mecanismos de aprendizaje que podr\u00edan verse facilitados o potenciados por el juego. Sin embargo, el estudio de las perspectivas de los propios actores acerca de sus procesos de aprendizaje ha sido considerado de manera menos intensiva y m\u00e1s reciente. Escuchar las perspectivas de los ni\u00f1os respecto del juego puede contribuir a un mejor dise\u00f1o de pol\u00edticas y de pr\u00e1cticas pedag\u00f3gicas en el campo de la educaci\u00f3n y del cuidado en la primera infancia.\r\nEl dise\u00f1o de la investigaci\u00f3n fue cualitativo y exploratorio, incorporando metodolog\u00edas que incluyen observaciones de campo, videograbaci\u00f3n y entrevistas semiestructuradas individuales y grupales con ni\u00f1os y adultos. Se trabaj\u00f3 con cuatro escuelas de diferentes contextos socioecon\u00f3micos y culturales, abordando a un total de 35 ni\u00f1os (16 ni\u00f1as y 19 ni\u00f1os). Se solicit\u00f3 el consentimiento informado de todos los adultos implicados y el asentimiento de todos los ni\u00f1os participantes, buscando resguardar en todo momento tanto su anonimato como su bienestar y participaci\u00f3n voluntaria.\r\nLa investigaci\u00f3n busc\u00f3 traer a la discusi\u00f3n las perspectivas de ni\u00f1os y ni\u00f1as acerca de sus oportunidades de juego y aprendizaje en momentos de transici\u00f3n educativa, contribuyendo a la reflexi\u00f3n acerca del rol del juego en las pr\u00e1cticas pedag\u00f3gicas.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2017 - Enero 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26363\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Rol del juego en la educaci\u00f3n parvularia: creencias y pr\u00e1cticas de educadoras de pre-kinder (NT1)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26363\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26363\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2016 - Enero 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad Cat\u00f3lica del Norte<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26438\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Imagen Corporal y Comportamiento Alimentario en una Muestra Comunitaria de Adultos Chilenos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26438\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26438\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Me adjudiqu\u00e9 este fondo de investigaci\u00f3n mientras era acad\u00e9mica de la escuela de psicolog\u00eda de la Universidad Cat\u00f3lica del Norte. A partir del mismo se public\u00f3 un art\u00edculo y se realizaron 4 tesis de pregrado[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2016 - Octubre 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26010\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Hippo pathway in the regulation of cell proliferation in germ and somatic cells in the ovary of the earwig Euborellia annulipes\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26010\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26010\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El estudio de la v\u00eda Hippo en el desarrollo del ovario de la tijereta es fundamental dado que esta v\u00eda celular controla procesos de proliferaci\u00f3n y muerte celular, lo que finalmente determina el tama\u00f1o del tejido. El ovario del insecto, durante su maduraci\u00f3n y desarrollo experimenta periodos asociados a proliferaci\u00f3n celular tanto de c\u00e9lulas som\u00e1ticas como germinales[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26033\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Diagn\u00f3stico de las creencias y conocimientos iniciales de estudiantes de pedagog\u00eda b\u00e1sica sobre la matem\u00e1tica escolar, su aprendizaje y ense\u00f1anza\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26033\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26033\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2016 - Octubre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26771\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Approximation of Conjunctive Query Evaluation\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26771\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26771\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Problems that cannot be solved by classical computers in reasonable time due to their high computational cost arise in many research areas. In general, the evaluation of conjunctive queries over relational databases belongs to those problems. Conjunctive queries form the core of the Structured Query Language (SQL) which became a de facto standard for querying and maintaining relational databases. This work is about developing new approximation techniques for conjunctive queries which cannot be evaluated in reasonable time. Our new approximation techniques should lead to significant improvements for data aided decision making, e.g., for early warning system which are based on the analysis of big data or to make business-critical decisions by analyzing big data. In the last decades, a very good understanding of the classes of conjunctive queries which can be evaluated in reasonable time has been gained and it has been proven that an under-approximation of a query always exists within each of those classes. However this approach is rather strict and some of the under-approximations can be rather uninformative, i.e., the under-approximation might return the empty result set while the original query would not. over-approximations might be helpful when this happens, as they return all answers to a query. One of our goals is to study the foundational aspects of over-approximations, including the existence problem and the problem of computing an approximation. Unfortunately, over-approximations do not always exist (within a class of queries which can be evaluated in reasonable time), and it is not even known to be decidable whether a conjunctive query admits an over-approximation. Therefore, another goal of the proposed work is the development of more liberal approximation techniques that yield some kind of quantitative guarantees. This means that they should guarantee that the result of the approximation is not too \u0093far\u0094 from the result of the original query over a set of databases of interest. Therefore we need to define a measure of disagreement between queries and\/or results. For conjunctive query evaluation, such measures do not exist up until now. Based on that measure, we study approximations whose disagreement with the result of the query they approximate is below a certain threshold. Furthermore, we investigate how the underlying data of a database can help us to find better approximations.\r\nIt has been shown that there are close relations between the approximation of conjunctive queries over relational databases and some classes of Semantic Web queries over semi-structured data. We also study possible connections between our approximation techniques and approximating Semantic Web queries.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2016 - Noviembre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26790\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Habilidades y Competencias para la Educaci\u00f3n Superior \u0096 Desarrollo de Instrumentos y Propuestas que aporten a un Nuevo Sistema de Admisi\u00f3n\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26790\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26790\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La construcci\u00f3n de un nuevo Sistema de Acceso a la Educaci\u00f3n Superior es materia de acuerdos t\u00e9cnicos, pol\u00edticos y sociales, fuera del alcance de un proyecto de I&D. Sin embargo, la calidad de este sistema depender\u00e1 fuertemente de la existencia de instrumentos que cuenten con evidencias de validez, que ampl\u00eden y diversifiquen el espacio de soluciones factibles.\r\n\r\nEl proyecto consiste en desarrollar instrumentos de selecci\u00f3n y caracterizaci\u00f3n de postulantes que pudiesen enriquecer el espacio de soluciones factibles para el nuevo Sistema de Acceso a la educaci\u00f3n superior. En particular, el producto final del proyecto corresponde a una bater\u00eda de 5 instrumentos que miden competencias y habilidades fundamentales para la educaci\u00f3n superior en las \u00e1reas de Lenguaje (Lectura y Escritura), Matem\u00e1tica, Ciencias y Habilidades Transversales. En esta bater\u00eda se incluyeron 3 pruebas de selecci\u00f3n (matem\u00e1tica, lectura y ciencias) cuya referencia curricular es solo a contenidos fundamentales, que no excedan el nivel de 2\u00b0 medio, y que son relevantes para el contexto t\u00e9cnico-profesional y humanista-cient\u00edfico. Tambi\u00e9n se incluyeron 2 instrumentos de caracterizaci\u00f3n de postulantes, que son el cuestionario de habilidades transversales y la prueba de competencia de escritura.\r\n\r\nEl desarrollo de los 5 instrumentos se realiz\u00f3 con la participaci\u00f3n activa de 150 expertos nacionales y 120 actores del sistema educacional chileno.\r\n\r\nLos instrumentos desarrollados responden a un Marco de Evaluaci\u00f3n que fue construido participativamente a lo largo del proyecto. El marco fue informado por la evidencia emp\u00edrica recogida en dos procesos de pilotaje de \u00edtems que se realizaron con cerca de 9.000 estudiantes chilenos de 4\u00b0 Medio. Adem\u00e1s, fue informado por las jornadas de socializaci\u00f3n y mesas de trabajo con expertos. Se promovi\u00f3 la m\u00e1s amplia participaci\u00f3n de actores diversos en la definici\u00f3n del Marco de Evaluaci\u00f3n de cada prueba, en el entendido que este debe corresponder a un acuerdo social acerca de lo que consideramos relevante y pertinente de ser medido en los instrumentos considerando las necesidades de la admisi\u00f3n a la educaci\u00f3n superior tanto universitaria como t\u00e9cnico-profesional.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2016 - Octubre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26792\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Mapa de g\u00e9neros de formaci\u00f3n acad\u00e9mica en Filosof\u00eda e Ingenier\u00eda El\u00e9ctrica: continuidades y contrastes textuales, disciplinares y pedag\u00f3gicos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26792\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26792\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]En las \u00faltimas dos d\u00e9cadas se han multiplicado en Chile y Latinoam\u00e9rica las iniciativas de ense\u00f1anza de la lectura y la escritura en educaci\u00f3n superior y se ha conformado un espacio disciplinar interesado por investigar las pr\u00e1cticas letradas acad\u00e9micas, organizadas en g\u00e9neros de formaci\u00f3n acad\u00e9mica, en el marco de un proceso de masificaci\u00f3n del acceso a los estudios universitarios.\r\n\r\nEn la presente investigaci\u00f3n, se busca construir un mapa contrastivo de g\u00e9neros de formaci\u00f3n acad\u00e9mica escritos por estudiantes en diferentes etapas de la formaci\u00f3n de dos carreras de pregrado de la Universidad de Chile (Filosof\u00eda e Ingenier\u00eda El\u00e9ctrica) y elaborar un diagn\u00f3stico de las pr\u00e1cticas de lectura y escritura, de su ense\u00f1anza y su curricularizaci\u00f3n en ese \u00e1mbito. Se seleccionan dos g\u00e9neros por nivel y por carrera: dos de ingreso (examen presencial e informe de laboratorio), dos de transici\u00f3n (ensayo e informe de pr\u00e1ctica profesional) y dos de graduaci\u00f3n (tesis de licenciatura y memoria de pregrado), de forma tal de contrastar los diferentes rasgos discursivos y desaf\u00edos pedag\u00f3gicos y ret\u00f3ricos en cada etapa de la formaci\u00f3n.\r\n\r\nSe lleva a cabo un an\u00e1lisis cualitativo manual de contenidos en las entrevistas, grupos focales y materiales y de an\u00e1lisis del discurso (circulaci\u00f3n, estructura, metadiscurso e intertextualidad) en los textos estudiantiles. Estos resultados se cuantifican y se calcula la correlaci\u00f3n entre variables textuales y contextuales (disciplina y etapa formativa) y la distribuci\u00f3n de las respuestas en las encuestas.\r\n\r\nLos hallazgos de esta investigaci\u00f3n permitir\u00e1n conocer mejor los g\u00e9neros discursivos de formaci\u00f3n acad\u00e9mica en espa\u00f1ol, en particular en humanidades e ingenier\u00edas; comprender algunos de los v\u00ednculos entre las pr\u00e1cticas letradas, su organizaci\u00f3n curricular y los desaf\u00edos de su ense\u00f1anza y aprendizaje; y brindar insumos informados para fomentar y robustecer iniciativas de ense\u00f1anza de la lectura y escritura acad\u00e9micas en la instituci\u00f3n investigada, en el pa\u00eds y en la regi\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 2016H1D3A1908042<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2016 - Noviembre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Fundaci\u00f3n Nacional de la Investigaci\u00f3n, Ministerio de Ciencias y Tecnolog\u00eda, Corea del Sur<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26939\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Improving aquifer storage and recovery by developing groundwater flow delineation and characterization technology\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26939\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26939\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Desarrollo de tecnolog\u00edas de modelaci\u00f3n para evaluar y optimizar sistemas de recarga artificial[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> CAPES: 001<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2016 - Agosto 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>CAPES\/UNESP-PG<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27003\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27003\" aria-expanded=\"false\" aria-controls=\"collapse-27003\">\n                                            Implicaciones del calentamiento y el d\u00e9ficit h\u00eddrico en el desempe\u00f1o nutricional de dos pastos tropicales contrastantes (C4 y C3)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27003\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27003\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Prev\u00ea-se que o aquecimento global aumente a intensidade e a dura\u00e7\u00e3o dos eventos clim\u00e1ticos extremos, como secas, ondas de calor e inunda\u00e7\u00f5es, especialmente nas regi\u00f5es tropicais. Mudan\u00e7as clim\u00e1ticas afetam o crescimento de esp\u00e9cies forrageiras. No entanto, faltam informa\u00e7\u00f5es sobre os efeitos das mudan\u00e7as clim\u00e1ticas globais no desempenho nutricional de pastagens tropicais, especialmente em condi\u00e7\u00f5es de campo. N\u00f3s, assim, conduzimos dois experimento em campos com as forrageiras Panicum maximum e Stylosanthes capitata utilizando um sistema de temperatura controlada do aquecimento do ar (T-Face) e avaliou-se os efeitos de duas condi\u00e7\u00f5es de temperatura, (temperatura ambiente) e aquecimento moderado (2\u00b0C acima da temperatura ambiente) e dois n\u00edveis de disponibilidade h\u00eddrica, (irrigada e n\u00e3o irrigados), no ac\u00famulo de nutrientes, efici\u00eancia de uso de nutrientes (NUE), nos padr\u00f5es estequiom\u00e9tricos de C:N:P e na produ\u00e7\u00e3o de biomassa foliar. Ambos experimentos foram conduzidos utilizando um delineamento de blocos completos casualizados em arranjo fatorial. Nossos resultados revelaram que em plantas de P. maximum (pastagem C4) a concentra\u00e7\u00e3o foliar de N e P diminuiu sob estresse h\u00eddrico, o que aumentou as rela\u00e7\u00f5es C:N e C:P, enquanto o aquecimento aumentou a rela\u00e7\u00e3o N:P. A produ\u00e7\u00e3o de biomassa foliar foi prejudicada em at\u00e9 16% sob condi\u00e7\u00f5es de estresse h\u00eddrico e temperatura ambiente, mas a produ\u00e7\u00e3o de biomassa foi melhorada em 20% sob condi\u00e7\u00f5es de aquecimento e irriga\u00e7\u00e3o. Nossos resultados tamb\u00e9m mostraram que a instabilidade homeost\u00e1tica em condi\u00e7\u00f5es de seca resultou na diminui\u00e7\u00e3o da produ\u00e7\u00e3o de biomassa foliar, e concluiu-se que o aquecimento \u00e9 ben\u00e9fico apenas para o crescimento das plantas em condi\u00e7\u00f5es bem irrigadas. Enquanto isso, a seca diminuiu a NUE de K, Ca e B e a biomassa seca das folhas, enquanto o crescimento das ra\u00edzes foi estimulado. No entanto, sob aquecimento e irriga\u00e7\u00e3o aumentaram a biomassa seca das folhas, a biomassa seca das ra\u00edzes, a densidade do comprimento das ra\u00edzes, a \u00e1rea superficial da raiz e a NUE de N, P, K, Ca, Mg, Cu, Mn e Zn. Por outro lado, no segundo experimento com plantas de S. capitata (pastagem C3), nossos resultados mostraram que as condi\u00e7\u00f5es de seca reduziram as concentra\u00e7\u00f5es de f\u00f3sforo (P) e aumentaram a rela\u00e7\u00e3o N:P nos diferentes \u00f3rg\u00e3os da planta. Descobrimos que a produ\u00e7\u00e3o de biomassa acima do solo diminuiu significativamente sob condi\u00e7\u00f5es de seca e de alta temperatura (wSaT e wSeT); observamos uma diminui\u00e7\u00e3o no conte\u00fado de nitrog\u00eanio (N), na rela\u00e7\u00e3o folha\/infloresc\u00eancia e rela\u00e7\u00e3o folha\/caule, e um aumento na rela\u00e7\u00e3o C:N nos \u00f3rg\u00e3os vegetativos. No entanto, sob condi\u00e7\u00f5es quentes e irriga\u00e7\u00e3o, a biomassa das folhas aumentou aproximadamente 33%. Conclu\u00edmos que o aquecimento em condi\u00e7\u00f5es bem regada e sem restri\u00e7\u00f5es na disponibilidade de nutrientes no solo, pode aumentar a produ\u00e7\u00e3o de biomassa vegetal, presumivelmente devido a um n\u00edvel mais alto da homeostase estequiom\u00e9trica.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26034\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            El desaf\u00edo de ense\u00f1ar matem\u00e1tica de primaria a bachillerato en los primeros a\u00f1os de profesi\u00f3n en Chile y en M\u00e9xico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26034\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26034\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto desarrollado en conjunto con equipo de INEE de M\u00e9xico.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2016 - Diciembre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26791\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Investigaci\u00f3n e Innovaci\u00f3n en el Desarrollo de Competencias de Lecto-escritura Acad\u00e9mica\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26791\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26791\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> W083SMKGW<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2016 - Diciembre 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Departamento de Medio Ambiente, Agua y Recursos Naturales, Gobierno de Australia Meridional, Australia<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26938\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Development of Adelaide Plains (AP) groundwater model\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26938\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26938\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Desarrollo de un modelo num\u00e9rico de aguas subterr\u00e1neas de las Planicies de Adelaida, Australia.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2016 - Abril 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26076\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Di\u00e1logos del Reconocimiento. Indagaciones visuales de unas identidades mapuche &#8211; fotograf\u00eda mapuche infantil\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26076\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26076\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto de creaci\u00f3n e investigaci\u00f3n a cargo del CIIR (Centro de Estudios Interculturales e Ind\u00edgenas) de la Pontificia Universidad Cat\u00f3lica de Chile.\r\nSu ejecuci\u00f3n se realiz\u00f3 en el colegio municipal Kemal Ataturk de la comuna de Lo Prado con estudiantes de ascendencia mapuche.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26205\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Cognitive biases and strategies underlying school mathematics: The case of fraction comparison (1160188)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26205\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26205\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2016 - Abril 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26411\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Din\u00e1mica neuronal eferente desde la corteza auditiva al receptor coclear durante paradigmas de atenci\u00f3n selectiva en pacientes con tinnitus y chinchillas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26411\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26411\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> CONICYT\/FONDECYT\/1161417<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2016 - Marzo 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27123\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            \u00bfQui\u00e9n es responsable del desarrollo local? Una geograf\u00eda pol\u00edtica del neoestructuralismo en \u0093comunas de exportaci\u00f3n\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27123\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27123\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]\u00bfQui\u00e9n es responsable del desarrollo local? La respuesta depende de muchos factores y perspectivas sobre la naturaleza del desarrollo y del modo en que surge. De particular inter\u00e9s en este proyecto es c\u00f3mo se manifiesta en localidades espec\u00edficas ligadas a procesos de producci\u00f3n y procesamiento para la exportaci\u00f3n. Se vincula con la tradici\u00f3n de la geograf\u00eda pol\u00edtica que se ha enfocado en el rol del Estado en procesos de desarrollo territorial bajo presiones de globalizaci\u00f3n y del \u0093desarrollo hacia afuera\u0094 desde los 1970s. De all\u00ed surge el concepto de neoestructuralismo, en comparaci\u00f3n con el neoliberalismo donde actores privados toman un rol decisivo en la orientaci\u00f3n del desarrollo. La geograf\u00eda pol\u00edtica se interesa por los actores detr\u00e1s de las transformaciones territoriales para determinar derechos y responsabilidades. Si bien hay instrumentos de regulaci\u00f3n que condicionan acciones sobre el territorio, tambi\u00e9n coexisten distintas perspectivas, ideas y planteamientos de desarrollo territorial que resultan en relaciones de cooperaci\u00f3n y conflicto. En este proyecto se identifican como articulaciones p\u00fablico-privadas.\r\n\r\nEl proyecto busca destrabar esa diversidad de perspectivas y sus manifestaciones en comunas donde se concentra el modelo econ\u00f3mico chileno: las comunas de exportaci\u00f3n. La pregunta sobre la responsabilidad por el desarrollo local surge en el contexto en que la sociedad civil entra cada vez m\u00e1s como actor en asociaci\u00f3n con el Estado y el sector privado, compitiendo por determinar la orientaci\u00f3n del desarrollo y reclamando sobre la distribuci\u00f3n de los beneficios y las externalidades negativas; el t\u00e9rmino zonas de sacrificio ha surgido para definir esta distribuci\u00f3n desigual. En el debate nacional sobre la descentralizaci\u00f3n y el reparto de los efectos del modelo exportador resalta la discusi\u00f3n sobre escalas, de producci\u00f3n y procesamiento ligado a las actividades econ\u00f3micas de exportaci\u00f3n. En esta discusi\u00f3n han emergido con fuerza durante las \u00faltimas dos d\u00e9cadas los conceptos de neoestructuralismo, gobernanza, legitimidad, articulaci\u00f3n o asociatividad, poder y descentralizaci\u00f3n. Es clave aplicar estas construcciones conceptuales en pr\u00e1cticas y territorios espec\u00edficos para reconocer su potencial para interpretar y explicar los dispares resultados del desarrollo ligado a la exportaci\u00f3n de recursos naturales.\r\n\r\nEl objetivo central de esta investigaci\u00f3n es analizar los roles y responsabilidades del Estado y del sector empresarial en la articulaci\u00f3n p\u00fablico-privada en Chile y sus efectos en comunas especializadas en actividades de exportaci\u00f3n entre 2000 y 2014. Esto considera el per\u00edodo en que se ha destacado el papel de la participaci\u00f3n e involucramiento ciudadano, aunque desde distintos enfoques y metas. Es por esta raz\u00f3n que el proyecto examinar\u00e1 seis comunas que han experimentado presiones de tres sectores productivos con evidente protagonismo del Estado, del empresariado y de la ciudadan\u00eda: Calama y Copiap\u00f3 para la miner\u00eda, Quemchi y Quell\u00f3n para la salmonicultura y Nacimiento y Constituci\u00f3n para la actividad forestal. Adicionalimente, se busca matizar los conceptos y perspectivas actuales con dos conceptos centrales: spatial fix de David Harvey, que indica la forma en la cual el capital aprovecha y condiciona el uso del territorio, y fricci\u00f3n territorial, un concepto en proceso de elaboraci\u00f3n por los autores para comunicar las formas de capturar e incorporar los beneficios de producci\u00f3n y exportaci\u00f3n en el territorio de extracci\u00f3n o procesamiento.\r\n\r\nPara lograr el objetivo se aplicar\u00e1 una metodolog\u00eda mixta basada en entrevistas con actores claves para determinar posiciones y perspectivas respecto a responsabilidades y procesos de desarrollo local, y an\u00e1lisis de flujos de capital \u0096patentes, inversiones en infraestructura, empleo, aportes culturales (responsabilidad social), entre otros. Los datos generados por las entrevistas ser\u00e1n sometidos a an\u00e1lisis tem\u00e1ticos, mientras que los flujos de capital ser\u00e1n expresados en t\u00e9rminos de vol\u00famenes, localizaciones (SIG) y flujos intra e intercomunales para graficar el tipo o prop\u00f3sito del flujo, los montos asociados, y a qu\u00e9 agenda corresponden. Esta metodolog\u00eda se contextualiza en un enfoque de casos de estudio con el que se espera vincular las posiciones de diversos actores frente a otros, evidenciar los aportes que contribuyen al desarrollo local y el grado de articulaci\u00f3n en las decisiones de inversi\u00f3n y captaci\u00f3n de beneficios del modelo exportador. Los resultados contribuir\u00e1n a una mejor precisi\u00f3n de lo que se entiende por los roles y responsabilidades de actores en esas comunas, que a su vez influye en la definici\u00f3n de pol\u00edticas, planes y programas dise\u00f1ados para fomentar la descentralizaci\u00f3n, fortalecer el desarrollo sustentable local y asegurar una articulaci\u00f3n p\u00fablico-privada capaz de reducir conflictos y mejorar la calidad de vida.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2016 - Marzo 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26020\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Capitalizando el rol predictor de las Competencias Matem\u00e1ticas Tempranas: dise\u00f1o y validaci\u00f3n de un programa de enriquecimiento matem\u00e1tico para el ciclo inicial basado en el M\u00e9todo Abierto Basado en N\u00fameros y Resoluci\u00f3n de Problemas (M\u00e9todo ABN)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26020\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26020\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto Fondecyt 1160980 se plante\u00f3 como principal desaf\u00edo el determinar el impacto que pudiera\r\ntener en Chile, la adaptaci\u00f3n de los lineamientos del M\u00e9todo Abierto Basado en N\u00fameros (M\u00e9todo ABN) implementado como un programa de apoyo al desarrollo favorable de las Competencias Matem\u00e1ticas Tempranas (CMT) para el nivel NT2, espec\u00edficamente, analizando el fortalecimiento de las CMT en los estudiantes de NT2, primero y segundo b\u00e1sico; en aspectos como el rendimiento escolar; en la capacidad para resolver problemas; en sus niveles de logro en conocimientos claves de la asignatura; en la actitud hacia la asignatura, todo ello comparado con grupos que siguen una metodolog\u00eda tradicional[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> (Cooperaci\u00f3n Internacional) CNPq-428473<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2016 - Marzo 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Conselho Nacional de Desenvolvimento Cient\u00edfico e Tecnol\u00f3gico<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26627\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estudo gen\u00f4mico amplo associativo para a resist\u00eancia de podrid\u00e3o no colmo causada por Fusarium verticillioides em cole\u00e7ao n\u00facleo de milho tropical\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26627\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26627\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]NA[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> PRONEX<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2016 - Junio 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Conselho Nacional de Desenvolvimento Cient\u00edfico e Tecnol\u00f3gico<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26629\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Evaluation of the maize breeding program of \u0093pipoca corn\u0094 for Value of Cultivation andUse tests (VCU)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26629\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26629\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]NA[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1160471<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2016 - Marzo 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26167\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Efectos de la ense\u00f1anza expl\u00edcita y contextualizada de la gram\u00e1tica y el l\u00e9xico en la calidad de la escritura de estudiantes de 6\u00b0 B\u00e1sico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26167\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26167\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]FONDECYT Regular 2016 (proyecto n\u00ba1160471)\r\nCargo: Co-Investigadora (Investigador responsable: Carmen Sotomayor, UChile).\r\nMarzo 2016 \u0096 Marzo 2019[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> IT15I10002<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2016 - Marzo 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26168\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Ense\u00f1anza y evaluaci\u00f3n de la escritura mediante una plataforma tecnol\u00f3gica colaborativa.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26168\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26168\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]FONDEF 2015 (proyecto n\u00ba IT15I10002)\r\nCargo: Co-Investigadora (Investigador responsable: Carmen Sotomayor, UChile).\r\nMarzo 2016 \u0096 Mayo 2018[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2016 - Octubre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26258\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Centro de Modelamiento Matem\u00e1tico (CMM)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26258\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26258\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]-\tInvestigador asociado. Centro de Modelamiento Matem\u00e1tico (CMM). Centro Basal N\u00ba AFB-170001, Director: Alejandro Maass. Marzo 2016-actual.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2016 - Marzo 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26259\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Role of Fur in the systemic response of Enterococcus faecalis and its impact on in vivo infectiveness under different nutritional status of iron.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26259\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26259\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Fondecyt de Iniciaci\u00f3n a\u00f1o 2015 N\u00b011150679. CONICYT. Proyecto titulado: Role of Fur in the systemic response of Enterococcus faecalis and its impact on in vivo infectiveness under different nutritional status of iron. Instituciones patrocinantes: Universidad de Chile y Universidad de O\u0092Higgins. Marzo 2015-Diciembre 2018.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2016 - Marzo 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>COES<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26748\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            (In)Justicia transicional y los Mapuche despu\u00e9s de la dictadura en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26748\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26748\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Materia Espec\u00edfica: Entender las din\u00e1micas por las cuales el pueblo Mapuche vivenci\u00f3 la dictadura y las maneras en que los dispositivos de justicia transicional representaron a este pueblo.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> MCTI\/CNPq\/ANA N\u00ba 23\/2015<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2016 - Diciembre 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Consejo Brasile\u00f1o de Desarrollo Cient\u00edfico y Tecnol\u00f3gico (CNPq) y Agencia Nacional de Aguas<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27002\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Impacto del aumento de la temperatura y el estr\u00e9s h\u00eddrico en el desempe\u00f1o molecular, bioqu\u00edmico, fisiol\u00f3gico, productivo y reproductivo de dos especies forrajeras tropicales en experimentos de simulaci\u00f3n clim\u00e1tica futura\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27002\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27002\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La temperatura y la humedad del suelo afectan fuertemente el valor nutricional y la digestibilidad de las plantas forrajeras a trav\u00e9s de cambios en la composici\u00f3n qu\u00edmica de la hoja o la proporci\u00f3n de tejidos de la hoja. En este proyecto, nuestro objetivo fue evaluar las modificaciones anat\u00f3micas de la hoja de dos especies forrajeras tropicales, Stylosanthes capitata (C3) y Megathyrsus maximus (C4) en condiciones c\u00e1lidas (+2 \u00b0C) en condiciones de riego abundante y secano e investigar las interacciones entre alteraciones anat\u00f3micas de las hojas, composici\u00f3n qu\u00edmica de las hojas y digestibilidad de las hojas. Los experimentos se realizaron en condiciones de campo utilizando un sistema de mejora controlada por aire libre de temperatura (T-FACE). Observamos que las plantas a temperaturas elevadas produjeron hojas con estomas m\u00e1s peque\u00f1os y tejido mes\u00f3filo m\u00e1s delgado y un grosor total de hoja reducido, lo que podr\u00eda afectar el intercambio de gases. Por otro lado, la reducci\u00f3n de la humedad del suelo aument\u00f3 la densidad estom\u00e1tica y el grosor de la epidermis adaxial. En ambas especies, la concentraci\u00f3n de las fracciones fibrosas de las hojas aument\u00f3 en condiciones c\u00e1lidas y sin riego, mientras que la concentraci\u00f3n de prote\u00edna cruda y la digestibilidad disminuyeron. Sin embargo, la digestibilidad de la hoja se asoci\u00f3 con la composici\u00f3n qu\u00edmica de la hoja m\u00e1s que con la proporci\u00f3n de diferentes tejidos de la l\u00e1mina de la hoja. Concluimos que, aunque ambas especies desarrollaron modificaciones anat\u00f3micas en las hojas para aclimatarse en condiciones de calentamiento futuro, el valor nutricional y la digestibilidad de las hojas se reducir\u00e1n, lo que podr\u00eda afectar la producci\u00f3n ganadera futura y las emisiones de metano de los rumiantes.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2015 - Junio 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26413\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            International Network for Auditory and Cognition Center\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26413\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26413\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2015 - Marzo 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26728\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Aprendizaje por exposici\u00f3n a los est\u00edmulos: una perspectiva evolutiva y comparada de las interacciones con los procesos de atenci\u00f3n, percepci\u00f3n, memoria y motivaci\u00f3n (N\u00ba Proyecto: 11140017).\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26728\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26728\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 3160164<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27075\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            MEDICI\u00d3N IN-SITU DE LA DENSIDAD DE DISLOCACIONES EN METALES BAJO ENSAYOS DE TRACCI\u00d3N Y COMPRESI\u00d3N\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27075\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27075\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las dislocaciones son la principal fuente de comportamiento pl\u00e1stico de metales, sin embargo, es muy dif\u00edcil de estudiar cuantitativamente su comportamiento. Con el fin de mejorar esta situaci\u00f3n, se ha propuesto utilizar su interacci\u00f3n con las ondas el\u00e1sticas como una sonda no invasiva. Recientemente, se han demostrado, utilizando espectroscopia de resonancia Ultrasonido (RUS), que un aumento de densidad de dislocaciones en aluminio por un factor de 6 conduce a un cambio de la velocidad de las ondas de cizalle del orden de 1, una cantidad que puede medirse con una precisi\u00f3n del orden de 0,1%.  \r\n\r\nSe propone entonces estudiar la contribuci\u00f3n de las dislocaciones a las propiedades mec\u00e1nicas en dos sistemas de inter\u00e9s: En primer lugar, metales poli-cristalinos, en particular muestras de cobre y de aluminio. En segundo lugar, se propone estudiar muestras con estructura de capas m\u00faltiples, en particular sistemas de capas intercaladas de cobre y de niobio. El objetivo de largo plazo de esta investigaci\u00f3n es permitir el desarrollo de la tecnolog\u00eda de ultrasonido como una herramienta no invasiva para la caracterizaci\u00f3n de materiales.\r\n\r\nSe investigar\u00e1 en primera instancia la contribuci\u00f3n de las dislocaciones a las constantes el\u00e1sticas de metales poli-cristalinos, continuando un estudio anterior. Se realizar\u00e1n nuevas medidas con muestras m\u00e1s puras de aluminio y de cobre, utilizando RUS en primera instancia. Como primer objetivo se plantea obtener un n\u00famero mayor de muestras, con condiciones m\u00e1s extremas que las ya analizadas aumentando el rango de dislocaciones estudiado. Adem\u00e1s de las medidas en el r\u00e9gimen lineal usando RUS, se realizar\u00e1n medidas de par\u00e1metros no-lineales que pueden ser caracterizados a mayores amplitudes de excitaci\u00f3n. Estas medidas pueden ser realizadas con el mismo montaje experimental de RUS. Adem\u00e1s, se propone hacer un an\u00e1lisis ultras\u00f3nico tanto lineal como no lineal en un montaje de deformaci\u00f3n est\u00e1ndar donde las medidas se realizar\u00e1n in situ.\r\n\r\nEn segundo lugar, se propone caracterizar muestras de cobre-niobio, con estructura de capas m\u00faltiples. La motivaci\u00f3n de este tema radica en el hecho que las interfaces del estado s\u00f3lido juegan un papel importante en la determinaci\u00f3n de las propiedades de los materiales compuestos, especialmente de los materiales estructurales destinados para el servicio en aplicaciones de energ\u00eda. En la actualidad, las muestras multi-capas de cobre-niobio pueden ser preparadas en tama\u00f1os \u00fatiles para RUS (desde mil\u00edmetros hasta cent\u00edmetros). Pueden ser fabricas con pocas capas (del orden de 10 capas) y espesores de d\u00e9cimas de mm cada una, o con muchas capas (del orden de 3.10&#8308;) y espesores de 10 nm cada una. La motivaci\u00f3n es obtener mediciones precisas de las constantes el\u00e1sticas efectivas de las muestras mediante hip\u00f3tesis del tipo homogeneizaci\u00f3n, y correlacionar sus valores con la cantidad de interfaces presentes. A primer orden, si dos muestras tienen la misma cantidad de niobio y cobre pero con diferentes n\u00fameros de capas y espesores, el proceso de homogenizaci\u00f3n m\u00e1s simple indica que las propiedades mec\u00e1nicas deben ser iguales. En la pr\u00e1ctica, se espera una contribuci\u00f3n de las interfaces, lo cual no ser\u00e1  despreciable cuando existan una cantidad considerable de ellas. La relaci\u00f3n con las dislocaciones radica en el hecho que estas interfases tienen dislocaciones de tipo misfit, y dependiendo de la orientaci\u00f3n de su vector de Burgers y de su densidad, su contribuci\u00f3n a la elasticidad de la interface ser\u00e1 distinta.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11150209<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2015 - Octubre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26169\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estudiantes vulnerables con resultados destacados en lectura: estudio de sujetos, familias y escuelas que fomentan la resiliencia acad\u00e9mica.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26169\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26169\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]FONDECYT Iniciaci\u00f3n 2015 (proyecto n\u00ba 11150209)\r\n\r\nThis investigation is built upon two hypotheses: a) There are factors linked to resilience and reading comprehension that establish a difference between the resilient students and the rest of the children that share their vulnerability condition. b) It is possible to control these factors in order to trigger and foster resilience. To prove these hypotheses, the general objective of this investigation is: To Determine which factors explain the excellent outcomes in reading comprehension of those students coming from an unprivileged socio-economic context.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2015 - Noviembre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26454\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Using free-living diazotrophic bacteria and aerobic degraded wheat straw to improve nitrogen fertility in crop systems\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26454\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26454\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2015 - Octubre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26543\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Associative Mechanisms of Extinction Cues\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26543\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26543\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto busc\u00f3 examinar los mecanismos tras el fen\u00f3meno de claves de recuperaci\u00f3n de la memoria de la extinci\u00f3n del miedo condicionado en ratas. Finalmente, logr\u00f3 presentar resultados parciales tanto en miedo condicionado como en aprendizaje apetitivo, indicando que una clave de extinci\u00f3n no logra reducir la recuperaci\u00f3n de respuesta.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2015 - Octubre 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26339\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            On the role of viscosity on the energy flux cascading on capillary wave turbulence\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26339\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26339\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Waves are ubiquitous in nature. They are all around us in our daily lives, we find them in several contexts, in particular in fluids. They usually involve a complex variety of interaction processes, and di&#8629;erent mechanisms. Of our particular inter- est is the case of waves at the interface between two fluids when they are perturbed. When strongly forced, the nonlinear interactions can produce a turbulent-like regime called wave turbulence. Theoretical, numerical and experimental studies have made a great deal of progress on this subject, and yet, there are several aspects that have not been properly addressed, namely the role of viscosity on the energy flux as it cascades through di&#8629;erent scales or the physical origin of the intermittency phenomenon.\r\nIn this proposal, we will consider the problem of capillary wave turbulence from an experimental and numerical point of view. One of the main complications to study surface wave turbulence is that, in the same system, there is involvement of di&#8629;erent types of waves, such as the case of gravito-capillary wave turbulence. Thus, it becomes of foremost importance to study wave turbulence on the presence of only one type of waves. Thereby, in order to study pure capillary wave turbulence, gravity waves must be negligible. We propose to study a system of capillary surface waves at the interface of two immiscible and incompressible fluids, water and silicon oil, of almost equal densities and layer depths, thus preventing the action of gravity. By changing the kinematic viscosity &#9003;, and density &#8674; of both fluids, it is possible to control the relation between injected and dissipated power, thus exploring several regimes in a simple and controlled way.\r\nWe pose to implement the technique called Free-surface synthetic Schlieren that allows a reconstruction of the instantaneous surface topography. Velocity fields will be explored by using the standard Particle Image Velocimetry. We will make use of an already existing experimental setup which will be modified in order to accomplish these techniques adequately. With these measurements we will be able to compute the spectrum in frequency f and wavevector k, hence accessing to statistical and dynamical properties of capillary wave turbulence, such as intermittency, or the function of the injected power on the system. We also propose to use the open source solver GERRIS and make a systematic study on the role of viscosity on the cascading of the energy flux.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 15150003<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2015 - Octubre 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27129\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Center Research on Marine Ecosystems of High Latitudes \u0096 IDEAL\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27129\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27129\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El Centro IDEAL desarrolla investigaci\u00f3n interdisciplinaria que integra ciencias naturales y sociales para generar conocimiento cient\u00edfico relevante para la conservaci\u00f3n y gobernanza de los sistemas marinos australes.\r\n\r\nSus l\u00edneas de trabajo (o dimensiones) se estructuran en torno a:\r\n\r\nProcesos f\u00edsicos y cambio clim\u00e1tico\r\nAnaliza la variabilidad ambiental (temperatura, circulaci\u00f3n oce\u00e1nica, hielo marino) y sus efectos sobre los ecosistemas. Incluye fen\u00f3menos como el calentamiento global y la acidificaci\u00f3n del oc\u00e9ano.\r\nEcosistemas, biodiversidad y funcionamiento ecol\u00f3gico\r\nEstudia la estructura y din\u00e1mica de los ecosistemas marinos, desde microorganismos hasta especies emblem\u00e1ticas, abordando su resiliencia, productividad e interacciones tr\u00f3ficas.\r\nMicrobiolog\u00eda y biogeoqu\u00edmica\r\nExamina el rol de microorganismos en los ciclos de nutrientes y en el funcionamiento del oc\u00e9ano austral, incluyendo su respuesta a cambios ambientales.\r\nDimensi\u00f3n humana, usos y gobernanza\r\nAborda la relaci\u00f3n entre sociedad y ecosistemas marinos, incluyendo pesca, acuicultura, turismo y conservaci\u00f3n, as\u00ed como los marcos institucionales y de pol\u00edtica p\u00fablica en contextos subant\u00e1rticos y ant\u00e1rticos.\r\nIntegraci\u00f3n y modelaci\u00f3n de sistemas socio-ecol\u00f3gicos\r\nDesarrolla enfoques integrados para comprender los sistemas acoplados humano-naturaleza, apoyando la toma de decisiones mediante modelos y escenarios.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2015 - Octubre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26412\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            De la Presbiacusia a la demencia: Un enfoque B\u00e1sico-Cl\u00ednico\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26412\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26412\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2015 - Octubre 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25979\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Evaluaci\u00f3n bibliogr\u00e1fica y estad\u00edstica de las estrategias estacionales coordinadas de tratamiento contra Caligus rogercresseyi para su optimizaci\u00f3n a trav\u00e9s de un protocolo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25979\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25979\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 304201\/2014-6<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2015 - Enero 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>CNPq, Brasil y TWAS, Academia Mundial de Ciencias, Italia<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27004\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27004\" aria-expanded=\"false\" aria-controls=\"collapse-27004\">\n                                            Cambios en el uso del suelo y el empleo de biofertilizantes para la nutrici\u00f3n de cultivos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27004\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27004\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Edital CNPq: CNPq\/TWAS - Doutorado-Sanduiche no Pais \/Sandwich PHD Fellowship - SWP 2014 - Vig\u00eancia: 01\/08\/2015 a 31\/01\/2016 (6 meses). Ci\u00eancia do Solo - Per\u00edodo de bolsa TWAS finalizado - 304201\/2014-6 \r\nComo parte de este proyecto de investigaci\u00f3n se publicaron dos art\u00edculos que se nombran a continuaci\u00f3n: \r\n\r\n*Olivera-Viciedo, D (AC)., Prado, R.M., Lizcano, R., Salas, D., Nascimento, L.C., Calero, A., Pe\u00f1a, K., Betancourt, C. (1\/8). 2020. Physiological role of silicon in radish seedlings under ammonium toxicity. Journal of the Science of Food and Agriculture, (FI=4.125, Q1), v. 100, p. 5637-5644. Indizaci\u00f3n: (ISI\/WoS, Scopus). https:\/\/doi.org\/10.1002\/jsfa.10587\r\n\r\n*Olivera-Viciedo, D (AC)., Prado, R., Lizcano, R., Nacimiento, L., Calero, A., Theodore, L and Castellano, L. (1\/7). 2019. Silicon supplementation alleviates ammonium toxicity in sugar beet (Beta vulgaris L.). Journal of Soil Science and Plant Nutrition. (FI=3.612, Q2), v. 19. p. 413-419. Indizaci\u00f3n: (ISI\/WoS, Scopus). https:\/\/doi.org\/10.1007\/s42729-019-00043-w[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2015 - Agosto 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26323\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            The Chilean Coastal Orographic Precipitation Experiment (CCOPE)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26323\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26323\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]The Chilean Coastal Orographic Precipitation Experiment (CCOPE) was conducted during the austral winter of 2015 (May\u0096August) in the Nahuelbuta Mountains (peak elevation 1.3 km MSL) of southern Chile\r\n(38\u00baS). CCOPE used soundings, two profiling Micro Rain Radars, a Parsivel disdrometer, and a rain gauge network to characterize warm and ice-initiated rain regimes and explore their consequences for orographic precipitation[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2015 - Abril 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26886\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Impacto de la mosca blanca (Bemisia sp.) en cultivos agroecol\u00f3gicos y su comparaci\u00f3n con cultivos tradicionales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26886\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26886\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26206\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Contribution of perception and long term memory processes in perceptual learning (1150289)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26206\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26206\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> F911437<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2015 - Marzo 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Ministerio de Educaci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26170\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            La producci\u00f3n escrita de estudiantes y escuela en base a resultados SIMCE, factores contextuales y modelos de buenas pr\u00e1cticas docentes\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26170\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26170\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto es de alta relevancia para todo el equipo que trabaj\u00f3 en \u00e9l puesto que signific\u00f3 introducir un enfoque sociocultural a los estudios de la ense\u00f1anza de la escritura que hasta el momento se realizaban en el CIAE. Desde esta perspectiva se considera la escuela como un espacio cultural, al igual que el hogar de los estudiantes, ambas culturas, dialogan, se enfrentan o se contraponen en determinados contextos y con fines espec\u00edficos. Este enfoque sobre el estudio de la escritura, no hab\u00eda sido desarrollado antes en Chile.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2015 - Enero 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>COES<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26749\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Consecuencias de la acci\u00f3n colectiva para el bienestar: La movilizaci\u00f3n estudiantil en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26749\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26749\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Materia Espec\u00edfica: Estudio de la relaci\u00f3n entre participaci\u00f3n en acciones colectivas y el bienestar entre estudiantes universitarios en Chile.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> Proyecto Fondecyt Posdoctorado.  3160352<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2015 - Noviembre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26750\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            How representations of the historical past influence present day intergroup relations and acculturation dynamics: The case of the Mapuche in Chile and of Congolese immigrants in Belgium\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26750\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26750\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este proyecto estaba enfocado en entender las memorias colectivas del pueblo Mapuche sobre la historia de Chile (previo y post independencia de Espa\u00f1a) y entender como los contenidos y la construcci\u00f3n de estas memorias colectivas se relacionan con la percepci\u00f3n de las relaciones intergrupales entre personas Mapuche y chilenas no-ind\u00edgenas en la actualidad. Fue el primer proyecto en enfocarse en el rol de las memorias colectivas para entender las percepciones de conflicto y violencia existentes en la actualidad en relaci\u00f3n con el pueblo Mapuche y su aspecto m\u00e1s novedoso y de alto impacto fue el an\u00e1lisis de estos fen\u00f3menos de manera cualitativa, algo que no se hab\u00eda hecho en el \u00e1rea de la psicolog\u00eda social anteriormente en Chile. Con un acercamiento cualitativo al fen\u00f3meno, logramos evidenciar caracter\u00edsticas particulares de la manera en que el pueblo Mapuche (re)construye su historia y sus vivencias al largo del tiempo, evidenciando que su cultura y cosmovisi\u00f3n permean estos procesos de una manera diferente a, por ejemplo, personas chilenas no-ind\u00edgenas. Adem\u00e1s, las reflexiones desarrolladas durante el proceso de terreno y producci\u00f3n de datos con comunidades Mapuche nos permitieron desarrollar tambi\u00e9n una nueva l\u00ednea de investigaci\u00f3n sobre las din\u00e1micas especificas y adaptaciones metodol\u00f3gicas necesarias para producir datos con pueblos originarios, respetando su cultura y cosmovisi\u00f3n en este proceso. Esta l\u00ednea de investigaci\u00f3n despert\u00f3 inter\u00e9s y curiosidad de distintas comunidades acad\u00e9micas en el mundo y llev\u00f3 a que fuera invitada dos veces a hablar de estos temas en las conferencias anuales de la International Society of Political Psychology en 2020 y 2021.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 11140576.<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2015 - Marzo 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26237\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Palatability in pigs. The pleasure of consumption.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26237\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26237\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Fondecyt Iniciaci\u00f3n[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2015 - Octubre 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26260\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Centro de Regulaci\u00f3n del Genoma (CRG)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26260\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26260\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]-\tInvestigador asociado. Centro de Regulaci\u00f3n del Genoma (CRG). Centro FONDAP FONDAP N\u00b015090007, Director: Miguel Allende. Marzo 2015-actual.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2015 - Diciembre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26261\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Metal metabolism in soil bacterial communities from an extreme environment: A comparative genomics analysis.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26261\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26261\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Fondecyt Regular 2015- N\u00b01151384. CONICYT. Proyecto titulado: Metal metabolism in soil bacterial communities from an extreme environment: A comparative genomics analysis. Instituciones patrocinantes: Universidad de Chile y Universidad de O\u0092Higgins. Investigador responsable Dr. Mauricio Gonz\u00e1lez. Marzo 2014-Diciembre 2018.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2015 - Enero 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26751\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            MapuMedia: Representaciones de los Mapuche en cuatro peri\u00f3dicos nacionales chilenos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26751\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26751\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Materia Espec\u00edfica: Entender la manera en que se representa el \u0093conflicto Mapuche\u0094 en medios de comunicaci\u00f3n nacionales en Chile al largo del tiempo. An\u00e1lisis de prensa.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26063\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fondo Rector Juvenal Hern\u00e1ndez Jaque\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26063\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26063\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Este fondo cubre la edici\u00f3n por un comit\u00e9 externo y la publicaci\u00f3n del libro \"Literatura para infancia, adolescencia y juventud: Reflexiones desde los estudios literarios.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2015 - Diciembre 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26793\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Iniciativas de Lectura y Escritura en la Educaci\u00f3n Superior en Latinoam\u00e9rica (ILEES)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26793\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26793\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> REDES140104<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2015 - Marzo 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26171\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Understanding the relevance of human agency for educational research, policy and practice.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26171\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26171\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]REDES 2014 (proyecto REDES140104)\r\nUnderstanding the relevance of human agency for educational research, policy and practice.  Cargo: Investigadora (Investigadora responsable: Carolina Holtheuer, UChile).\r\nEnero 2015 \u0096 marzo 2016[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2015 - Diciembre 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Beca BRIC de movilidad acad\u00e9mica (ULB)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26752\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Representations of the colonial past and present-day intergroup relations between former colonizer and colonized communities in Belgium and Portugal\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26752\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26752\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Materia Espec\u00edfica: Entender la manera en que las represenciones del colonialismo belga en Congo influyen en las relaciones entre personas belgas y migrantes de Congo residentes en B\u00e9lgica[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2015 - Agosto 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26364\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transici\u00f3n y articulaci\u00f3n entre la Educaci\u00f3n Parvularia y la Educaci\u00f3n General B\u00e1sica en Chile: Caracter\u00edsticas y evaluaci\u00f3n\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26364\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26364\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> (INFRADEV-3- Ref: 676564)<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2015 - Diciembre 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>European Commission<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26857\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26857\" aria-expanded=\"false\" aria-controls=\"collapse-26857\">\n                                            EPOS: European Plate Observing System, Implementation Phase. European Commission\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26857\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26857\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]EPOS, the European Plate Observing System, is a multidisciplinary, distributed research infrastructure that facilitates integrating data, data products, and facilities from the solid Earth science community in Europe.\r\n\r\nParticipaci\u00f3n como miembro del equipo investigador.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2014<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26498\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Instituto Milenio para la Investigaci\u00f3n de Imperfecciones de Mercado y Pol\u00edticas P\u00fablicas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26498\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26498\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Las fallas del mercado son dif\u00edciles de entender, debido a una variedad de factores que se\r\nconfunden entre s\u00ed. La pol\u00edtica p\u00fablica enfrenta el desaf\u00edo de distinguir cada uno de esos\r\nfactores. El Instituto Milenio para el estudio de Imperfecciones del Mercado y Pol\u00edticas\r\nP\u00fablicas, MIPP, desarrolla y difunde investigaci\u00f3n de vanguardia sobre las respuestas de\r\npol\u00edtica p\u00fablica a las distintas fallas del mercado. Para ello, el MIPP desarrolla herramientas\r\npara evaluar dise\u00f1os de pol\u00edticas p\u00fablicas y realiza recomendaciones que mejoren el bienestar\r\ny el funcionamiento de mercados y organizaciones.\r\nLos investigadores de este Instituto Milenio desarrollan investigaci\u00f3n de frontera en\r\nOrganizaci\u00f3n Industrial, Macroeconom\u00eda, Finanzas y Econom\u00eda Pol\u00edtica. Los resultados de\r\nestas investigaciones se presentan en prestigiosas conferencias en el mundo y se publican en\r\nlas mejores revistas acad\u00e9micas en Econom\u00eda, Ciencias Pol\u00edticas y Administraci\u00f3n.\r\nEl MIPP genera tambi\u00e9n herramientas metodologicas que permiten entregar informaci\u00f3n\r\nrelevante para la toma de decisiones del sector p\u00fablico y privado; genera puntos de encuentro,\r\ndiscusi\u00f3n e intercambio de conocimiento entre investigadores nacionales e internacionales; y\r\ndesarrolla actividades de difusi\u00f3n abiertas a la comunidad que incluyen talleres de Econom\u00eda y\r\nsesiones de Educaci\u00f3n Financiera para peque\u00f1os empresarios.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Diciembre 2014 - Mayo 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26365\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Understanding the relevance of human agency for educational research, policy and practice\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26365\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26365\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2014 - Septiembre 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26340\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Attach\u00e9 temporaire d\u0092enseignement et de recherche (ATER)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26340\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26340\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Position that involved teaching an undergraduate course to students from ENS along with research on an experimental study of wave turbulence.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2014 - Octubre 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26707\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Variational Problems Under Conic Constraints\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26707\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26707\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2014 - Agosto 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Corporaci\u00f3n de Fomento de la Producci\u00f3n - CORFO<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26695\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Matem\u00e1ticas Felices II:  Juegos Basados en Ciencia para Aprender los N\u00fameros\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26695\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26695\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Desarrollo de Juegos de Tablero para promover aprendizajes de la matem\u00e1tica.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2014 - Noviembre 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25980\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Nuevos prototipos de sets de biomarcadores sangu\u00edneos aplicados al diagn\u00f3stico predictivo de enfermedades en acuicultura \u0096 Bioblood y Bioplasma\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25980\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25980\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2014 - Abril 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26011\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Caracterizaci\u00f3n de la v\u00eda Hippo en el ovario de la tijereta Forficula auricularia (L) como mecanismo celular regulador de crecimiento de un tejido\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26011\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26011\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El proyecto busca establecer a la tijereta como insecto modelo para estudios de oog\u00e9nesis y caracterizar una v\u00eda de se\u00f1alizaci\u00f3n celular fundamental en el tama\u00f1o de un \u00f3rgano. Adem\u00e1s de establecer t\u00e9cnicas de silenciamiento g\u00e9nico en este organismo.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2014 - Mayo 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26795\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Transitividad y agentividad: el principio de gradualidad para la explicaci\u00f3n sem\u00e1ntico-discursiva de los procesos. Un enfoque sist\u00e9mico-funcional\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26795\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26795\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2014 - Mayo 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>The Rufford Small Grants<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26486\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            What Can Reveal the Tree Rings of Nothofagus Macrocarpa about the Conservation State of the Mediterranean Deciduous Forest of Central Chile?\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26486\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26486\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetivo del proyecto es evaluar la din\u00e1mica de crecimiento y la variabilidad gen\u00e9tica de las poblaciones remanentes de N. macrocarpa y su vulnerabilidad al cambio clim\u00e1tico. Para ello, realizaremos muestreos y trabajos de campo en cinco \u00e1reas de estudio en la zona central de Chile utilizando t\u00e9cnicas cl\u00e1sicas de dendrocronolog\u00eda y gen\u00e9tica forestal.\r\n\r\nLos resultados generados permitir\u00e1n destacar el estado de conservaci\u00f3n del bosque mediterr\u00e1neo caducifolio, caracterizado por la especie end\u00e9mica N. Macrocarpa. De esta manera, podr\u00edamos entender y evaluar la degradaci\u00f3n hist\u00f3rica que ha afectado a este bosque, que a pesar de su actual estado de conservaci\u00f3n a\u00fan tendr\u00eda un rol ecol\u00f3gico clave en Chile central. Adem\u00e1s, nuestros resultados podr\u00edan ser utilizados en la toma de decisiones p\u00fablicas para la conservaci\u00f3n y restauraci\u00f3n ecol\u00f3gica de este ecosistema, considerando que Chile est\u00e1 pasando por un momento de discusi\u00f3n, modificaci\u00f3n e implementaci\u00f3n de sus leyes forestales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> Fondecyt No. 1141303<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2014<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26864\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Volcanism on the Nazca Plate: plumes and plate tectonic processes\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26864\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26864\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]buscar[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #48A2F9\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2014 - Diciembre 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#48A2F9 !important; color:#FFF\">En Ejecuci\u00f3n<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26308\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Centro Avanzado de Enfermedades Cr\u00f3nicas (ACCDiS)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26308\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26308\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> CNPq No 014\/2010<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2014 - Diciembre 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Conselho Nacional de Desenvolvimento Cient\u00edfico e Tecnol\u00f3gico<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26628\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Characterization of Brazilian soybean germplasm by genotyping, and genome wide association mapping of genes and QTLs for agronomic traits\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26628\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26628\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]NA[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2014<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26035\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Herramientas para fortalecer la formaci\u00f3n de profesores de educaci\u00f3n b\u00e1sica basadas en experiencias de ense\u00f1anza de la matem\u00e1tica en aula\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26035\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26035\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Fondef IT13I10005\r\nInvestigadora responsable Salom\u00e9 Mart\u00ednez[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2014 - Febrero 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26124\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fondecyt Regular 1141195 &#8211; Early risk of asthma in children exposed to in-utero maternal obesity. An epigenetic-mediated programming of immune function\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26124\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26124\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Asthma is a chronic disease that affects young children starting mostly in the first years of life; with a high prevalence across countries globally. In Santiago, Chile, the prevalence of asthma among children 6-7 and 13-14 years of age is 11% and 15%, respectively; and for recurrent wheezing during the first year of life is as high as 22%. Asthma is the fourth most common cause of disability-adjusted life years for children aged 10\u009614 yrs and an important cause of reduced quality of life and exercise tolerance, higher rates of school absenteeism and hospitalization. A recent study done in Santiago reports that 30.4% of all infants visits to the emergency department presented with wheezing and wheezing exacerbations accounted for 8.4% hospital admission. Treatment of asthma currently focuses in reducing symptoms; however the morbidity remains high due to limited curative options and the unresolved etiology of asthma. There are no well-established methods or diagnostic tools to indentify the risk to develop asthma, and the current accepted practice base the diagnosis on parental or self-reported symptoms. One of the most accepted tools to predict asthma early in the infancy was developed by our team (the Asthma Predictive Index); and has been incorporated in most asthma early diagnosis guidelines globally. However, there is growing evidence supporting that beside genetic inheritance, maternal health during gestation represents an important factor conditioning the risk of asthma in the offspring. Thus a better understanding of pathogenesis of asthma in the neonatal period throughout uncovering the mechanisms that explain the associations between fetal life cues with asthma would contribute to an early prevention and treatment. \r\nImmune function plays a central role in the development of asthma, but the relative contribution of different immune cell types (i.e. mast cells, eosinophils, lymphocytes, neutrophils and monocytes\/macrophages) to this disease is still under examination. Nonetheless, it is clear that asthma presents an altered expression of pro-inflammatory molecules (IL-12, TNF-&#945;) and anti-inflammatory mediators (IL-10, IL-4). Notably, modulation of M1-M2 polarization of monocytes and macrophages seems to be crucial for the development of altered immune response in asthma, and this process would be tightly regulated by epigenetic mechanisms (i.e. DNA methylation, histone modifications). Numerous clinical and epidemiological studies have underlined the detrimental or beneficial role of nutritional factors in complex inflammation-related disorders such as allergy and asthma. It is now progressively better established that most of this risk is influenced in the very early stages of development, by a process of \u0093early life programming\u0094 in which epigenetic mechanisms  will actively participates. Remarkably, maternal obesity during gestation associates with increased plasma levels of TNF-&#945; at birth, and a 4-fold increased risk of asthma in the offspring. Also growing data show that epigenetic mechanisms exert an important control on the altered immune function observed in autoimmune and inflammatory controlling the expression of key genes. However, whether maternal obesity during pregnancy influences the immune function and the risk of asthma in the offspring throughout epigenetic mechanisms has not been addressed.\r\nIn this context we propose that \u0093Maternal obesity during pregnancy increases the risk of developing asthma in the offspring by an epigenetic-mediated programming of the inflammatory response in monocytes. This programmed inflammatory response is characterized by a higher expression of pro-inflammatory molecules (IL-12, TNF-&#945;) along with a lower expression of anti-inflammatory mediators (IL-10, IL-4R&#945;) which occurs due to changes in the methylation status of the promoter regions of these immune response- key genes\u0094. Studying a cohort of 400 children (0\u00963 years old) born from mother with or without obesity during pregnancy this proposal will address whether: a) the increased risk of asthma in children born from obese mother can be observed at 3 years of life; b) the increased asthma risk in these children associates with an altered immune reactivity in monocytes at birth; and c) the altered immune reactivity in monocytes occurs along with changes in the DNA methylation status at the promoter regions of asthma-related genes. \r\nThis study would reveal new molecular markers contributing to early diagnosis of asthma during childhood, as well as establish the real effects of epigenetic mechanisms modeling the immune function and responses at long term.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2014 - Marzo 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de Chile<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26238\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Anhedonia en perros. Efecto del estr\u00e9s sobre la preferencia, aceptabilidad y palatabilidad en edulcorantes y concentrados proteicos.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26238\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26238\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto FIV. Facultad de Ciencias Veterinarias y Pecuarias. Universidad de Chile. \r\n\tInvestigador Responsable[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2014 - Diciembre 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de Chile<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26239\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Palatabilidad en cerdos. Aproximaciones al placer del consumo.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26239\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26239\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Proyecto U-Inicia. Universidad de Chile. \r\n\tInvestigador Responsable[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2014 - Julio 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26794\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Alfabetizaci\u00f3n acad\u00e9mica en universidades p\u00fablicas metropolitanas: contraste de variables institucionales, did\u00e1cticas y ling\u00fc\u00edsticas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26794\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26794\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2013<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26207\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Integraci\u00f3n de un investigador emergente de alto nivel de especializaci\u00f3n para potenciar la investigaci\u00f3n de la educaci\u00f3n matem\u00e1tica dentro del plan estrat\u00e9gico del Centro de Investigaci\u00f3n Avanzada en Educaci\u00f3n (CIAE) de la Universidad de Chile (79130029)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26207\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26207\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2013 - Octubre 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26286\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Proyecto FONDECYT Postdoctorado N\u00ba 3140162: \u0093Evaluation of the organic micropolluntants, nutrient and organic matter removal contained on domestic wastewater treated by constructed wetlands\u0094.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26286\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26286\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2013 - Octubre 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25994\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Modulaci\u00f3n de la autofagia por el receptor de inositol trifosfato (IP3R) en distrofia muscular de Duchenne\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25994\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25994\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2013<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26036\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estudio exploratorio del proceso de cambio del profesor de matem\u00e1tica desde su propia perspectiva\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26036\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26036\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2013 - Abril 2014<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26366\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estudio Exploratorio sobre la inclusi\u00f3n de la perspectiva de Derechos del Ni\u00f1o en la Formaci\u00f3n Inicial de Educadoras de P\u00e1rvulos en Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26366\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26366\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> UNISS\/KPU-MASV<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2013 - Junio 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Association of Universities and Colleges of Canada (AUCC) in Kwantlen Polytechnic University, British Columbia<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27005\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27005\" aria-expanded=\"false\" aria-controls=\"collapse-27005\">\n                                            Microorganismos nativos una propuesta relevante y sustentable para llevar a cabo en pr\u00e1cticas de manejo de suelos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27005\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27005\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetivo del trabajo fue evaluar diferentes formas de aplicaci\u00f3n de microorganismos eficientes (ME) en diferentes cultivos y sobre el suelo, tanto en clima tropical (Cuba), como en clima fr\u00edo (Canad\u00e1). Se llevaron a cabo diversos experimentos en los que se concluy\u00f3 que el empleo de ME en aplicaciones foliares correspondientes a 50, 100, 150 y 200 ml\/L mejora el crecimiento y consecuentemente la producci\u00f3n de las plantas, siendo ese efecto m\u00e1s significativo en la dosis de 100 ml\/L en cultivos como el tomate, zanahorias, pepino y arroz. En los par\u00e1metros del suelo, contribuyen con la degradaci\u00f3n de la materia org\u00e1nica y con el proceso de mineralizaci\u00f3n de los compuestos org\u00e1nicos.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2013 - Agosto 2014<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Corporaci\u00f3n de Fomento de la Producci\u00f3n - CORFO<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26696\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Matem\u00e1ticas Felices: Juegos Basados en Ciencia para Aprender los N\u00fameros\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26696\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26696\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Creaci\u00f3n de Metodolog\u00edas de ense\u00f1anza basadas en juegos num\u00e9ricos[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2013 - Octubre 2013<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26367\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Sistema de Modelamiento del Ambiente F\u00edsico de Aprendizaje (MAFA) para el Mejoramiento de la Calidad de la Educaci\u00f3n Parvularia\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26367\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26367\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2013 - Diciembre 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26796\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estudio sociodiscursivo contrastivo de la monograf\u00eda como g\u00e9nero de formaci\u00f3n en carreras de humanidades\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26796\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26796\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Se reconoce que el rasgo com\u00fan a la monograf\u00eda en las carreras de humanidades es que introduce a los estudiantes en la escritura de investigaci\u00f3n. Sin embargo, la distinci\u00f3n entre configuraciones del g\u00e9nero responde a rasgos sociodiscursivos que pueden ligarse a las culturas disciplinares en las que se inscribe. En este sentido, los estudios exploratorios sugieren que las monograf\u00edas de la carrera de Historia parecen tener como objetivo general la puesta en relaci\u00f3n de fuentes bibliogr\u00e1ficas brindadas al estudiante; las monograf\u00edas de Filosof\u00eda suelen centrarse en un an\u00e1lisis textual propio del estudiante con pocas referencias al estado de la cuesti\u00f3n o a las lagunas en el conocimiento sobre el tema; mientras que las monograf\u00edas de Educaci\u00f3n y de Letras seguir\u00edan m\u00e1s de cerca el modelo de creaci\u00f3n de nicho de los art\u00edculos de investigaci\u00f3n (Swales, 1990, 2004) que consiste en el aporte de conocimiento nuevo a partir del relevo bibliogr\u00e1fico, la identificaci\u00f3n de problemas y la presentaci\u00f3n de hip\u00f3tesis y hallazgos.\r\n\r\nEste proyecto de investigaci\u00f3n busca hacer aportes al conocimiento de los g\u00e9neros acad\u00e9micos de formaci\u00f3n en espa\u00f1ol, generar insumos para la elaboraci\u00f3n de materiales did\u00e1cticos para la alfabetizaci\u00f3n avanzada a lo largo del grado en carreras de humanidades y colaborar con la discusi\u00f3n sobre la reforma de los planes de estudios en la Facultad de Filosof\u00eda y Letras en relaci\u00f3n con la formaci\u00f3n en pr\u00e1cticas de lectura y escritura acad\u00e9micas a lo largo del grado.\r\n\r\nPara cometer este prop\u00f3sito se construye un corpus digital con monograf\u00edas correspondientes a las carreras de Educaci\u00f3n, Filosof\u00eda, Historia y Letras de la Facultad de Filosof\u00eda y Letras (UBA) con el objeto de i) brindar una descripci\u00f3n de la monograf\u00eda tanto en sus rasgos comunes a las carreras como en sus rasgos espec\u00edficos disciplinarmente a partir de dimensiones discursivas relevantes y ii) establecer relaciones bidireccionales entre las diferentes manifestaciones del g\u00e9nero y las diferentes culturas disciplinares en las que se inscribe.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2013 - Mayo 2014<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26798\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            G\u00e9neros acad\u00e9micos y acceso a la educaci\u00f3n superior para docentes abor\u00edgenes biling\u00fces\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26798\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26798\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 243587898<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Junio 2013 - Junio 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Deutsche Forschungsgemeinschaft (DFG)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26924\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-26924\" aria-expanded=\"false\" aria-controls=\"collapse-26924\">\n                                            Methods for Exploration, Manipulation and Safe Human-Robot-Interaction with Capacitive Tactile Proximity Sensors\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26924\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26924\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]In the previous project the research focus was on the sensing principle and the development of prototype modules for a tactile proximity sensor (TPS). In the current project the focus is on the methods and algorithms with which the events in the near proximity of the robots can be modelled by means of these sensors. Collectively, the TPS on the robot surface and gripper constitute a smart skin. The application scenarios here are the Active Exploration of the Environment, Grasping and the Safe Human-Robot-Interaction. The methods to be developed will improve significantly on the quality of state of the art methods and expand the horizon of possible solutions for these problems. The capacitive measuring principle and the spatial resolution in both, the tactile and proximity modalities, enable an area-wide and distance based coverage of the robot surroundings. It is the first time that algorithms for Exploration, Grasping and Safe-Human-Robot-Interaction are presented that rely simultaneously on both tactile and proximity sensing with spatial resolution. The goal of the Exploration is to research which methods and strategies enable the robot to acquire a contact- and proximity-based world-model by means of TPS. The quality of state of the art solutions for grasping should be improved significantly. For the Safe-Human-Robot-Interaction algorithms should be developed that adapt the robots path and velocity according to the current situation as determined by the TPS. Also, new algorithms should make a TPS-based Interaction possible with the goal of robot controlling and programming by the human through tactile and proximity input. Finally, according to the context of the task and situation at hand (Exploration, Manipulation and Interaction) the robot should show an appropriate behaviour which is given by a behavioural strategy that will also be developed. The starting point in the project is the TPS-modules which were successfully developed in the previous project. At the beginning, research will be focused on the algorithms for signal processing that extract robust features from TPS for higher level tasks. This step is followed by the integration of TPS into a robot system realizing the smart skin. Building on these steps the methods for Exploration, Manipulation and Safe-Human-Interaction are developed. Finally, the results of the project will be shown and evaluated in a combined demonstration scenario that includes a robot endowed with TPS.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2013 - Abril 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26887\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Desarrollo de biopesticidas a partir de nematodos entomopat\u00f3genos para el manejo de plagas agr\u00edcolas en la Rep\u00fablicas de Cuba y Venezuela\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26887\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26887\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2013 - Abril 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26889\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortalecimiento de Espacios para la Investigaci\u00f3n en el Centro de Estudios Bot\u00e1nicos y Agroforestales \u0096CEBA- (IVIC-Zulia)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26889\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26889\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2013 - Abril 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26890\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fortalecimiento de formaci\u00f3n para el manejo y protecci\u00f3n de recursos naturales renovables\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26890\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26890\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2013 - Abril 2014<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26891\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Respuesta de plantas de guayabo (Psidium guajava L.) a la inoculaci\u00f3n con hongos micorrizicos arbusculares (HMA) nativos e introducidos, bajo condiciones de vivero\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26891\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26891\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2013 - Abril 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26888\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Diagn\u00f3stico precoz de enfermedades de cacao como estrategia de soberan\u00eda alimentaria\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26888\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26888\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2013 - Abril 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Financiamiento Privado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26222\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Proyectos en convenio con empresas Agroquimicas en Italia\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26222\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26222\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]\u0095\tCBC (Europe) S.r.l. \u0093Lotta biologica al cancro batterico dell'actinidia (P. syringae pv. actinidiae, Psa) con uso di batteri antagonisti\u0094. Cesena (FC) \u0096 Italia.\r\n\u0095\tCBC (Europe) S.r.l. \u0093Efficacy in vitro of the biofungicide Amylo-X against different bacterial pathogen strains (Xanthomonas spp., Pseudomonas spp., Erwinia spp.) in comparison with the efficacy of KSF40 and SB9501 biofungicides\u0094. Cesena (FC) \u0096 Italia.\r\n\u0095\tConsorzio Kiwigold s.r.l. Consortile, Cesena (FC). \u0093Analisi microbiologica di polline di Actinidia pre- e post- trattamento antibatterico\u0094. Italia.\r\n\u0095\tValagro, Spa. \u0093Efficacy in vitro and in vivo of the product bioestimulante No. 3-2435 against Clavibacter michiganensis subsp. michiganensis, Xanthomonas vesicatoria e Pseudomonas syringae pv. actinidiae\u0094. Italia.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2013 - Febrero 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26125\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            FONDEF D11I1098 &#8211; Nueva formulaci\u00f3n farmacol\u00f3gica para el tratamiento y la prevenci\u00f3n de la hipertensi\u00f3n arterial y disfunci\u00f3n vascular: Respuesta integrada a una patolog\u00eda multifactorial.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26125\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26125\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]1.\tLa hipertensi\u00f3n arterial esencial es el principal factor de riesgo cardiovascular, con una prevalencia del 30-40 % en la poblaci\u00f3n adulta, que llega al 75% en mayores de 65 a\u00f1os. A pesar del desarrollo de f\u00e1rmacos, la efectividad de los tratamientos actuales es limitada. En cerca de 50% de los pacientes, el tratamiento farmacol\u00f3gico no logra controlar la presi\u00f3n arterial elevada. La hipertensi\u00f3n es de origen multifactorial, pero existe consenso que la disfunci\u00f3n endotelial juega un papel primordial en su desarrollo. La bio-disponibilidad del \u00f3xido n\u00edtrico (NO), que es el principal vasodilatador, est\u00e1 reducida en la mayor\u00eda de las enfermedades vasculares debido al estr\u00e9s oxidativo y al aumento de la expresi\u00f3n y actividad de arginasa, una enzima que compite por el sustrato del NO. Este proyecto desarrollamos una nueva combinaci\u00f3n farmacol\u00f3gica dirigida a proteger el NO, combinando las propiedades vasodilatadoras y anti-remodeladoras del inhibidor de la arginasa \u00e1cido 2(s)-Amino-6-Boronohexanoico (ABH) y de del antioxidante N-Acetilciste\u00edna (NAC). Buscamos introducir una nueva forma de enfocar el tratamiento para la hipertensi\u00f3n arterial, atacando con esta formulaci\u00f3n farmacol\u00f3gica los mecanismos moleculares que subyacen a la disfunci\u00f3n endotelial: baja bio-disponibilidad de NO y aumento del estr\u00e9s oxidativo. En un modelo de hipertensi\u00f3n en ratas inducido por hipoxia intermitente cr\u00f3nica, cuya presi\u00f3n fue monitorizada por telemetr\u00eda, evaluamos el efecto de la combinaci\u00f3n sobre la hipertensi\u00f3n arterial y la disfunci\u00f3n vascular. La combinaci\u00f3n ABH+NAC reduce la presi\u00f3n arterial elevada, revierte la reducci\u00f3n del di\u00e1metro interno de las arterias, regulariza la funci\u00f3n endotelial y contr\u00e1ctil en arterias y disminuye el estr\u00e9s oxidativo. No encontramos efectos adversos sobre la funci\u00f3n renal y hep\u00e1tica. Estos resultados dieron origen a la presentaci\u00f3n de dos solicitudes de patentes en Chile y de protecci\u00f3n CTP en el extranjero para un nuevo m\u00e9todo de s\u00edntesis de ABH y de los efectos ben\u00e9ficos de la combinaci\u00f3n sobre la hipertensi\u00f3n y disfunci\u00f3n endotelial. En conjunto con el Laboratorio Andr\u00f3maco se estableci\u00f3 una estrategia de propiedad industrial ex post, as\u00ed como las acciones cient\u00edfico-tecnol\u00f3gicas conducentes a las siguientes fases de desarrollo del medicamento: pruebas precl\u00ednicas en otros modelos de hipertensi\u00f3n, desarrollo gal\u00e9nico y\/o fase cl\u00ednica I. Dado que el resultado de producci\u00f3n de la formulaci\u00f3n  deber\u00e1 pasar a\u00fan por pruebas cl\u00ednicas antes de ser dispuesto a los beneficiarios, la patente de este nuevo f\u00e1rmaco podr\u00e1 ser utilizada como activo principal para capturar capital de inversi\u00f3n que permita continuar con este proceso, o bien para licenciar a empresas con inter\u00e9s en el rubro. Junto a la Fundaci\u00f3n del Adulto Mayor, desarrollamos actividades de extensi\u00f3n con la finalidad de informar a la comunidad y con ello contribuir a prevenir los efectos delet\u00e9reos de la hipertensi\u00f3n en la poblaci\u00f3n de mayor riesgo cardiovascular. En esta propuesta se espera validar una nueva terapia antihipertensiva que ataque los mecanismos fisiopatol\u00f3gicos principales de la disfunci\u00f3n vascular que conduce a la hipertensi\u00f3n arterial esencial.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2013 - Febrero 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26126\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fondecyt Regular 1130801. Modeling the epigenetic programming of vascular dysfunction by oxidative stress in the Intrauterine Growth Restricted fetus: role of prenatal antioxidants in preventing long-term vascular dysfunction.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26126\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26126\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Compelling evidence shows that adverse intrauterine conditions increase the risk to develop cardiometabolic diseases in the adulthood. This concept has been called \u0091Developmental Origins of Health and Disease\u0092 (DOHaD) and relies on the activation of mechanisms sensing and signaling a diversity of stimuli during early development that later lead to higher risk of disease. The mechanisms that have been broadly suggested to be involved in these processes are epigenetic modifications in key gene promoters that could \u0091record\u0092 normal and abnormal perinatal stimuli. \r\n   Intrauterine oxidative stress is a common feature in conditions with altered fetal growth (i.e. intrauterine growth restriction \u0096IUGR-, or macrosomia). Several cellular processes require the participation of pro-oxidant molecules which are normally neutralized by antioxidant defenses. However, under determined conditions the pro-oxidants overcome these defenses inducing oxidative stress. The latter is an important stimulus that regulates vascular function and cardiovascular physiology, playing a key role in the development of cardiovascular diseases, regulating negatively the bioavailability of the main vasodilator nitric oxide (NO). In addition, the vascular system presents a high phenotypic plasticity during life, which is modulated and restricted by epigenetic mechanisms (including DNA methylation, histone post-translational modifications and micro RNAs). \r\n   Interestingly, cultured placental endothelium derived from complicated pregnancies presents persistent abnormal phenotypes, characterized by altered expression of proteins involved in NO-dependent vasodilation (i.e. eNOS and arginase), suggesting an early onset of endothelial dysfunction. Preliminary data from in vitro experiments, show that this altered expression of eNOS in IUGR placenta-derived endothelial cells is accompanied by epigenetic alterations in the promoter of its gene. Moreover, these cells can be reprogrammed to a \u0093normal type\u0094, interfering with the molecular machinery that preserves the DNA methylation pattern. However, there are no studies addressing the role of the pro-oxidant status associated to IUGR on the epigenetic programming of placental vascular dysfunction, and whether these epigenetic changes reflect those present in other fetal vascular beds or in the adult cardiovascular system.\r\n   Therefore, we hypothesized that the in utero oxidative stress, that characterizes IUGR, induces an epigenetic programming of the endothelial function, which is linked to abnormal umbilical and fetal vascular reactivity and higher risk of adult cardiovascular disease. These epigenetic changes lead to an altered expression of endothelial function-related proteins and to their response to superimposed oxidative stress in umbilical and systemic arteries in the fetus and adult guinea pig. \r\n   If true, the development of IUGR in the presence of antioxidant treatment should prevent the vascular impairment in the fetus and the adult guinea pig. This hypothesis will be tested in an IUGR guinea pig model according to the following general aims (GA): GA-1. To determine whether the IUGR-associated oxidative stress induces endothelial dysfunction in umbilical and systemic arteries, altering the basal expression of proteins implicated in the NO-dependent vasodilation (NO-DV) pathway and their response to oxidative stress; GA-2. To determine in umbilical artery (UAEC) and aortic (AEC) endothelial cells whether endothelial dysfunction induced by fetal oxidative stress associates with epigenetic changes in the promoter of genes implicated in the NO-DV pathway, altering their response to oxidative stress in vitro; GA-3. To determine in adult life whether the IUGR-associated oxidative stress results in increased markers of endothelial dysfunction, oxidative stress and cardiovascular disease. GA-4. To determine in AEC of adults born with IUGR whether endothelial dysfunction induced by fetal oxidative stress is associated with epigenetic changes in the promoter of genes implicated in the NO-DV pathway and their response to oxidative stress in vitro, correlating them with those found at term of gestation. \r\n   IUGR will be induced by uterine artery ligation in a pregnant sow, and the role of oxidative stress in the vascular programming will be analyzed treating IUGR pregnancies with the antioxidant N-acetylcysteine. The acute effect of pro- and anti-oxidants on vascular reactivity and NO-dependent vasodilation will be determined by wire-myography in IUGR near-term fetuses and adults guinea pig arteries. Further, the presence of proteins related with NO-dependent vasodilation (eNOS, arginase, HO-1, NQO1 and DHFR) in these vessels will be determined by immunohistochemistry. Endothelial epigenetic programming will be analyzed in primary cell cultures from UAEC and AEC in near-term fetuses and AEC in adult guinea pigs. \r\n   Our expected outcome is to demonstrate that oxidative stress is one of the main sources of the IUGR-induced dysfunction in fetal and adult vascular beds. Further, we expect that the NAC treatment should be able to prevent partially or totally the programmed vascular impairment. This project is not only relevant to uncover the developmental mechanisms that determine short- and long-term vascular dysfunction, but also to propose eventual treatments in complicated pregnancies, that unfortunately present a very high rate in humans.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2013<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Estatal de Investigaci\u00f3n (AEI) de Espa\u00f1a<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26974\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Pensamiento funcional en Educaci\u00f3n Primaria: relaciones funcionales, representaciones y generalizaci\u00f3n\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26974\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26974\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]www.pensamientoalgebraico.es[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2013 - Junio 2014<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26044\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Regards crois\u00e9s sur la vie collective des enfants de 2-3 ans. Qualit\u00e9, socialisation et confrontation \u00e0 l\u0092alt\u00e9rit\u00e9 dans les diff\u00e9rentes structures collectives accueillant des enfants de 2-3 ans\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26044\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26044\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La investigaci\u00f3n, de tipo cualitativo y corte etnogr\u00e1fico, fue desarrollada en cuatro estructuras diferentes de atenci\u00f3n y educaci\u00f3n a la primera infancia en Francia que reciben a ni\u00f1os entre 2 y 3 a\u00f1os: una \u0093peque\u00f1a secci\u00f3n\u0094 de una \"\u00e9cole maternelle\"; una \"clase passerelle\" inserta tambi\u00e9n en una \"\u00e9cole maternelle\"; un \"jardin maternel\"; y una sala cuna o \"cr\u00e8che\". Combinando diversas t\u00e9cnicas \u0096 fundamentalmente observaci\u00f3n y filmaci\u00f3n de ni\u00f1os y ni\u00f1as, entrevistas en profundidad individuales y colectivas tanto con padres como con profesionales, utilizando como soporte parte del material audiovisual recopilado, y un trabajo experimental para recabar el punto de vista infantil \u0096 se indag\u00f3 en las principales modalidades de participaci\u00f3n e interacci\u00f3n desarrolladas por los ni\u00f1os y ni\u00f1as, as\u00ed como en las pr\u00e1cticas profesionales de socializaci\u00f3n por parte del equipo pedag\u00f3gico de cada estructura.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2013 - Julio 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26223\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Ricerche sul Psa Kiwi e PPV Drupacee: \u0093Sensibilit\u00e0 varietale a Ps. syringae pv. actinidiae di nuove accessioni di kiwi\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26223\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26223\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2013 - Diciembre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26729\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Aprendizaje, Percepci\u00f3n, Atenci\u00f3n, Memoria y Desarrollo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26729\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26729\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2013 - Diciembre 2014<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26797\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            G\u00e9neros acad\u00e9micos en la escritura de formaci\u00f3n de carreras de humanidades (Educaci\u00f3n, Filosof\u00eda, Historia y Letras)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26797\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26797\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2012 - Octubre 2014<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26390\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            VIU-FONDEF 120036. Nuevo sistema de an\u00e1lisis para la selecci\u00f3n de variedades resistentes a salinidad\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26390\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26390\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2012 - Octubre 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26324\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Coastal orographic precipitation process studies\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26324\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26324\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2012 - Diciembre 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26128\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fondequip EQM-120205 Plataforma para el estudio de Metilaci\u00f3n de DNA,PyromarkQ96\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26128\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26128\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2012 - Abril 2014<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26892\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Promoci\u00f3n del uso de insumos biol\u00f3gicos para el desarrollo de una agricultura sustentable en Venezuela\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26892\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26892\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2012 - Febrero 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26127\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Fondecyt Regular 1120928 &#8211; INTRAUTERINE PROGRAMMING OF HIPOXIA- AND OXIDATIVE STRESS-INDUCED VASCULAR RESPONSES IN PLACENTAL ENDOTHELIUM FROM IUGR AND MACROSOMIC FETUSES: EARLY EVIDENCE FOR EPIGENETIC-DRIVEN VASCULAR DYSFUNCTION\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26127\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26127\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Hay pruebas s\u00f3lidas de que tanto la restricci\u00f3n del crecimiento intrauterino (RCIU) y la macrosom\u00eda fetal (peso\r\nal nacer > 4000 g) est\u00e1n fuertemente asociados con el aumento del riesgo de enfermedades cr\u00f3nicas en la vida\r\nadulta (i.e. hipertensi\u00f3n arterial y diabetes tipo 2). La asociaci\u00f3n entre el desarrollo peri-concepcional y fetal con\r\nla salud en la vida adulta, llamada \u0093Programaci\u00f3n Fetal\u0094 se basa en la activaci\u00f3n de mecanismos de detecci\u00f3n\r\ny se\u00f1alizaci\u00f3n de una diversidad de est\u00edmulos durante el desarrollo temprano. Los mecanismos que han sido\r\nampliamente sugerido que participan en estos procesos son las modificaciones epigen\u00e9ticas que podr\u00edan\r\nregistrar los est\u00edmulos perinatales. Como testigo de los cambios perinatales a los que se ve expuesto el\r\nembri\u00f3n y luego el feto en su desarrollo y crecimiento est\u00e1 la placenta, que junto con estar constituida por tejido\r\nque regula el intercambio de nutrientes y la modulaci\u00f3n inmune est\u00e1 formada por una importante red vascular\r\nque permite obtener desde la sangre materna los nutrientes, el ox\u00edgeno, las se\u00f1ales hormonales y del sistema\r\ninmune. El sistema vascular de la placenta se proyecta igualmente en la circulaci\u00f3n sist\u00e9mica del feto, donde se\r\nsugiere que ocurren adaptaciones en las condiciones patol\u00f3gicas antes mencionadas (RCIU y macrosom\u00eda fetal\r\nsecundaria a obesidad materna), condicionando as\u00ed a estos ni\u00f1os a presentar un elevado riesgo de\r\nenfermedades cardiometab\u00f3licas en la vida adulta.\r\nEste proyecto propuso estudiar la presencia de marcas epigen\u00e9ticas (cambios en el patr\u00f3n de metilaci\u00f3n de\r\ncitosinas en la regi\u00f3n promotora de genes y cambios en la modificaci\u00f3n de histonas que participan en el estado\r\nde compactaci\u00f3n\/relajaci\u00f3n de la cromatina) en las c\u00e9lulas vasculares de la arteria umbilical (HUAEC), cambios\r\nen la funci\u00f3n vascular y expresi\u00f3n de genes, prote\u00ednas y actividad de enzimas claves en la funci\u00f3n vascular en\r\ntres grupos de gestantes: 1) gestantes normopeso con fetos de crecimiento normal denominados \u0093Adecuados\r\npara la Edad Gestacional\u0094 (AEG); 2) gestantes normopeso con fetos que presentaron Restricci\u00f3n del\r\nCrecimiento IntraUterino (RCIU) y 3) gestantes con obesidad pregestacional que tuvieron hijos que fueron\r\nGrandes para la Edad Gestacional (FMOM).\r\nLos objetivos y los resultados principales de este proyecto fueron:\r\n1) Estudiar el tono vascular de las arterias umbilicales y cori\u00f3nicas de la placenta en estas tres condiciones\r\ncl\u00ednicas con acento en la participaci\u00f3n de las v\u00edas dependiente de \u00f3xido n\u00edtrico, un vasodilatador dependiente\r\ndel endotelio, clave en el tono vascular placentario. Se determin\u00f3 que las arterias cori\u00f3nicas y placentarias de\r\nlos fetos RCIU y FMOM presentan disfunci\u00f3n vascular dependiente de \u00f3xido n\u00edtrico y que existe un desbalance\r\nentre la actividad de arginasa-2\/eNOS que favorece esta disfunci\u00f3n. (ver Krause et al. Placenta 2012; 2013;\r\nSchneider et al., Placenta 2015).\r\n2) Determinar si estos cambios en el tono vascular placentario y umbilical se correlacionan a cambios en la\r\nexpresi\u00f3n de genes y prote\u00ednas claves en la funci\u00f3n vascular (eNOS, Arg2, CAT-1) y de respuesta estr\u00e9s\r\noxidativo (NOX4, GPx-1, SOD-1 y HO-1) en los cultivos primarios de HUAEC de las tres condiciones cl\u00ednicas,\r\nas\u00ed como en los tejidos (cordones umbilicales y arterias cori\u00f3nicas) (ver Schneider et al., Placenta 2015). Se\r\ndetermin\u00f3 que estos vasos est\u00e1n marcados por una respuesta cr\u00f3nica a estr\u00e9s oxidativo, presentando una\r\nlimitada reserva vascular al estr\u00e9s oxidativo, comparado con los tejidos provenientes de embarazos AEG (ver\r\nSchneider et al., Placenta 2015).\r\n3) Estudiar la presencia de modificaciones epigen\u00e9ticas presentes en la regi\u00f3n promotora de los genes\r\nrelacionados con la v\u00eda de s\u00edntesis del \u00f3xido n\u00edtrico (NO) y determinar si la respuesta al estr\u00e9s oxidativo y\/o\r\nhipoxia est\u00e1n programadas epigeneticamente. Se determin\u00f3 que de todos los genes estudiados s\u00f3lo eNOS y\r\nArg2 presentan cambios en el patr\u00f3n de metilaci\u00f3n en la regi\u00f3n promotora (ver Krause et al., Epigenetics\r\n2013) que se correlacionan con las modificaciones de histonas encargadas de regular el estado de\r\ncompactaci\u00f3n de la cromatina (Caniuguir et al., en preparaci\u00f3n).\r\n4) Ahondar en la participaci\u00f3n de los mecanismos epigen\u00e9ticos (HDAC y DNMT) en la expresi\u00f3n basal de estos\r\ngenes en las tres condiciones cl\u00ednicas. Se determin\u00f3 muy elegantemente como NO es quien regula a nivel\r\nepigen\u00e9tico la apertura de la cromatina de arginasa 2 y su actividad transcripcional (ver Krause et al., Biochem\r\nPharmacol 2016).\r\nEl desarrollo de este proyecto tuvo como fruto 18 art\u00edculos en revistas indexadas, la mitad de ellos\r\ndirectamente relacionados con resultados de este proyecto y los otros de colaboraciones nacidas durante estos\r\na\u00f1os, que apuntan directamente a comprender los mecanismos que subyacen la programaci\u00f3n fetal de\r\nenfermedades cardiometab\u00f3licas en tejido placentario, en ni\u00f1os pre-adolescentes, modelos animales de RCIU y\r\nobesidad materna, proyectos cl\u00ednicos de seguimiento de ni\u00f1os, etc.\r\nEste proyecto aport\u00f3 en forma sustantiva a la generaci\u00f3n de nuevo conocimiento en relaci\u00f3n a los\r\nmecanismos moleculares que subyacen a la programaci\u00f3n vascular alterada en fetos con RCIU y FMOM,\r\nque est\u00e1n en mayor riesgo de desarrollar enfermedades vasculares en la vida postnatal, con la relevancia\r\ncl\u00ednica de la potencial aplicaci\u00f3n en la detecci\u00f3n temprana de factores de riesgo cardiovascular en el\r\nnacimiento.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> DI13-0033<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2012<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>DIUFRO<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26224\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Determinaci\u00f3n e incidencia de fitopat\u00f3genos en avellano europeo en el Sur de Chile\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26224\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26224\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2012<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26225\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Development of seed testing methods for pests and pathogens of plant health concern (TESTA)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26225\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26225\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2012 - Diciembre 2014<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26730\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Procesos y mecanismos perceptivos, atencionales y de memoria en el aprendizaje por exposici\u00f3n a est\u00edmulos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26730\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26730\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2012<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Fundaci\u00f3n Universidad de Las Palmas de Gran Canaria<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26865\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Eruption periodicity study for obtaining the volcanic hazard map of El Hierro Island (Canary Islands)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26865\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26865\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]buscar[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2012 - Enero 2013<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Programa de Becas Posdoctorales en la UNAM (Mexico)<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26901\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Estudio de la din\u00e1mica de la contaminaci\u00f3n fecal en el anillo de cenotes, Celest\u00fan y Dzilam de Bravo, Yucat\u00e1n.\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26901\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26901\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetiv\u00f3 del proyecto de investigaci\u00f3n era de identificar la presencia y las fuentes de\r\ncontaminaciones fecales en al anillo de cenotes en el estado de Yucat\u00e1n (zona con ecosistemas fr\u00e1giles\r\ny altamente productivos) a trav\u00e9s del desarrollo de marcadores qu\u00edmicos.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Noviembre 2011 - Noviembre 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26456\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Use of chemically stabilized compost together with selected arbuscular mycorrhizal fungi as a tool for the bioremediation of copper and arsenic polluted soils in the Puchuncav\u00ed Valley\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26456\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26456\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 3130635<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Octubre 2011 - Septiembre 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26416\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Mecanismos de modulaci\u00f3n eferente auditiva en un modelo de atenci\u00f3n selectiva en ratones gen\u00e9ticamente modificados y en chinchillas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26416\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26416\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Mecanismos de modulaci\u00f3n eferente auditiva en un modelo de atenci\u00f3n selectiva en ratones gen\u00e9ticamente modificados y en chinchillas: Se realizo medici\u00f3n de funcionamiento eferente auditivo en modelos modificados gen\u00e9ticamente y bajo inhibici\u00f3n farmacol\u00f3gica. Se evalu\u00f3 en una prueba conductual los resultados.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2011 - Junio 2014<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26799\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Multimodalidad y estrategias discursivas: el caso de las redes sociales en internet (Facebook y Twitter)\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26799\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26799\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2011 - Abril 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26893\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Red Interinstitucional para la protecci\u00f3n de cultivos frutales en el Estado Zulia, bajo un enfoque ecol\u00f3gico y sustentable\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26893\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26893\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2011 - Noviembre 2011<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26455\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Ensamble de aspectos complementarios: restauraci\u00f3n ecol\u00f3gica y\/o la rehabilitaci\u00f3n de ambientes degradados y su relaci\u00f3n con microorganismos promotores de crecimiento vegetal\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26455\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26455\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2011 - Marzo 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de Ghent<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26753\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Culpa y verg\u00fcenza desde una perspectiva cultural\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26753\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26753\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Materia Espec\u00edfica: Entender las expresiones y dimensiones de las emociones de culpa y verg\u00fcenza en distintas culturas; psicolog\u00eda transcultural.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 08\/58075-8<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2011 - Diciembre 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>FAPESP, BRASIL<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27006\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27006\" aria-expanded=\"false\" aria-controls=\"collapse-27006\">\n                                            Impacto del cambio clim\u00e1tico Mini-FACE para analizar los efectos del CO2 elevado y el calentamiento en la fotos\u00edntesis, la expresi\u00f3n g\u00e9nica, la bioqu\u00edmica, el crecimiento, la din\u00e1mica de nutrientes y el rendimiento de dos especies forrajeras tropicales c\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27006\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27006\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Durante este proyecto multidisciplinario financiado por la FAPESP se han conseguido hasta la fecha 24 art\u00edculo publicados en revistas internacionales de alto impacto, de los cuales soy autor o coautor en 8, y de ellos, en 4 soy el primer autor y de correspondencia. Mayores informaciones, as\u00ed como todos los art\u00edculos derivados de este proyecto se pueden encontrar en el siguiente enlace: https:\/\/bv.fapesp.br\/pt\/auxilios\/29555\/miniface-climate-change-impact-experiment-to-analyze-the-effects-of-elevated-co2-and-warming-on-phot\/[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2011 - Diciembre 2013<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26800\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Pr\u00e1cticas de escritura profesional en contexto empresarial\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26800\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26800\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2010 - Agosto 2011<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26802\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Relevamiento de consignas de evaluaci\u00f3n y tareas de escritura en tres carreras de la UNGS\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26802\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26802\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> STUDENTS FOR DEVELOPMENT. SFD-KPU<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Agosto 2010 - Enero 2013<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Canadian International Development Agency and Kwantlen Polytechnic University<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27007\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a class=\"accordion-button bg-transparent p-0 pe-2 collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-27007\" aria-expanded=\"false\" aria-controls=\"collapse-27007\">\n                                            Cambios en el uso de la tierra y el contenido de \u00e1cidos h\u00famicos de diferentes suelos debido al manejo agr\u00edcola\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27007\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27007\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Durante el proyecto \"Estudiantes para el Desarrollo\" entre la universidad de Kwantlen, Canad\u00e1 y la universidad de Sancti Sp\u00edritus Jos\u00e9 Mart\u00ed P\u00e9rez, se realizaron varias visitas de intercambio acad\u00e9mico e investigativos entre estudiantes e acad\u00e9micos de ambos paises. Adem\u00e1s se desarrollaron diversas investigaciones conjuntas que tributaron en capacitaci\u00f3n y producci\u00f3n cient\u00edfica.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Julio 2010 - Diciembre 2012<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26803\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            proyecto de investigaci\u00f3n-acci\u00f3n \u0093Talleres de Lectura y Escritura de G\u00e9neros Acad\u00e9micos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26803\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26803\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]La formaci\u00f3n del grado universitario no consiste solamente en la adquisici\u00f3n de contenidos sino, sobre todo, en la enculturaci\u00f3n de los estudiantes en las pr\u00e1cticas acad\u00e9micas que configuran las esferas disciplinares. Se trata de que los estudiantes se apropien de las formas socialmente consensuadas de construir, negociar y comunicar el conocimiento en la universidad. Un aspecto fundamental de este proceso de enculturaci\u00f3n es, justamente, la apropiaci\u00f3n de las pr\u00e1cticas de lectura y escritura cient\u00edfico-acad\u00e9micas. Entre 2010 y 2012, la Secretar\u00eda de Pol\u00edticas Universitarias del Ministerio de Educaci\u00f3n de la Naci\u00f3n financi\u00f3 mediante el Programa de Mejoramiento para Facultades de Humanidades (PROHUM) los Talleres de lectura y escritura de g\u00e9neros acad\u00e9micos en la Universidad de Buenos Aires. Originalmente dise\u00f1ados como talleres remediales de lectura y escritura, un equipo de ocho ling\u00fcistas expertos en did\u00e1ctica de la lectura y la escritura en el nivel superior determin\u00f3 que su dictado requer\u00eda, previamente, conocer las pr\u00e1cticas letradas reales de las carreras de humanidades.\r\n\r\nPor este motivo, los talleres se transformaron en un proyecto de investigaci\u00f3n-acci\u00f3n que, al tiempo que dise\u00f1aba y dictaba el programa de los cursos, llev\u00f3 a cabo tareas diversas de investigaci\u00f3n, publicadas o presentadas en congresos: se construy\u00f3 un corpus amplio con textos curriculares y estudiantiles; se caracterizaron g\u00e9neros acad\u00e9micos de formaci\u00f3n; se dio cuenta de pr\u00e1cticas de lectura en carreras como filosof\u00eda y letras; y se entrevist\u00f3 y encuest\u00f3 a diversos actores de la vida acad\u00e9mica en la instituci\u00f3n. Adem\u00e1s, durante el primer a\u00f1o de implementaci\u00f3n de los talleres se dictaron cursos de formaci\u00f3n de tutores de lectura y escritura acad\u00e9mica, que participaron en la puesta en funcionamiento de los cursos al a\u00f1o siguiente, y en la producci\u00f3n de materiales did\u00e1cticos. En el tercer y \u00faltimo a\u00f1o del proyecto, se socializaron las investigaciones realizadas y se reelaboraron y ampliaron los materiales did\u00e1cticos a partir de la experiencia de su puesta en pr\u00e1ctica el a\u00f1o previo, y se public\u00f3 el \u0093Manual de escritura para carreras de humanidades\u0094.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2010 - Abril 2011<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26894\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Creaci\u00f3n del Centro de Estudios Bot\u00e1nicos y Agroforestales\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26894\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26894\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> CONICYT\/FONDECYT\/1100519<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2010 - Marzo 2013<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27124\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Planificando una monocultura: actores y transformaciones territoriales en Chilo\u00e9 frente al desarrollo de la salmonicultura, 1982-2008\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27124\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27124\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]El objetivo de esta investigaci\u00f3n consiste en evaluar las transformaciones territoriales del desarrollo del sector salmonicultor entre los a\u00f1os 1982 y 2008 en la provincia de Chilo\u00e9. En particular, busca vincular estas transformaciones con los diversos actores que tienen injerencia en dichas transformaciones: sector p\u00fablico, sector privado y sociedad civil. Estos actores no est\u00e1n necesariamente localizados en la provincia, pero influyen en el curso de las transformaciones territoriales. La investigaci\u00f3n se basa en el concepto de monocultura, que refleja la importancia de un sector espec\u00edfico al orientar no s\u00f3lo la econom\u00eda local, sino los cambios socio-culturales, las transformaciones de paisaje y de calidad ambiental. La monocultura, entonces, no es solamente una monocultura de producci\u00f3n, sino una monocultura en el hecho que el desarrollo de la provincia est\u00e1 siendo planificado en funci\u00f3n del sector salmonicultor. Consideramos que la planificaci\u00f3n es el \u00e1mbito dentro de cual los actores generan decisiones que transforman los territorios. Estos procesos de planificaci\u00f3n no son s\u00f3lo p\u00fablicos, a trav\u00e9s de instrumentos de planificaci\u00f3n territorial, inversiones, etc., sino tambi\u00e9n privados.\r\n\r\nLa investigaci\u00f3n pretende contextualizar el desarrollo de la provincia en t\u00e9rminos de los roles y decisiones de estos actores, localizando este proceso de desarrollo dentro de la globalizaci\u00f3n contempor\u00e1nea y los debates asociados. Utilizamos el concepto de \u0093glocalizaci\u00f3n\u0094 de Eric Swyngedouw para entrar en estas din\u00e1micas de cambios locales y globales en torno de la producci\u00f3n y consumo de salmones cultivados. Al trabajar con la provincia en su totalidad, la investigaci\u00f3n busca hilar proyectos e investigaciones en la provincia realizados hasta la fecha en sectores o \u00e1reas de inter\u00e9s espec\u00edficos, como la historia, mitolog\u00eda y cultura, ecolog\u00eda, geograf\u00eda f\u00edsica del borde costero y comercio. La investigaci\u00f3n trabajar\u00e1 con estos fragmentos para ir reconstruyendo las transformaciones territoriales durante este periodo.\r\n\r\nLa metodolog\u00eda para enfrentar las cinco hip\u00f3tesis planteados \u0096una principal y otras cuatro ligadas a la primera\u0096, est\u00e1 basada en m\u00e9todos mixtos. El primero es el uso de metodolog\u00edas de evaluaci\u00f3n de sustentabilidad disponibles y su adaptaci\u00f3n al caso de estudio. La meta consiste en la formulaci\u00f3n de una metodolog\u00eda capaz de trazar la trayectoria del desarrollo de la provincia y contextualizarla en t\u00e9rminos de sustentabilidad, entendida como un aumento de bienestar sin degradaci\u00f3n del stock de capital natural cr\u00edtico. Este ejercicio requiere el manejo de bases de datos que en el caso seleccionado son limitadas, por eso la necesidad de adaptar las metodolog\u00edas existentes. En la investigaci\u00f3n tambi\u00e9n se emplear\u00e1n encuestas para complementar los datos objetivos disponibles. Estas encuestas buscan destacar opiniones y percepciones sobre las transformaciones generadas, para complementar el an\u00e1lisis de los cambios f\u00edsicos en los paisajes. Para entrar en m\u00e1s detalle sobre los actores, se desarrollar\u00e1n entrevistas semi-estructuradas con actores clave para indagar sobre las formas en que la planificaci\u00f3n formal e informal de la provincia avanza, y para determinar la importancia del sector salmonicultor en las toma de decisiones en diversos \u00e1mbitos. De particular inter\u00e9s para la investigaci\u00f3n es entender los cambios en las relaciones en \u00e1reas rurales y \u00e1reas urbanos durante el periodo, estudiando las \u00e1reas peri-urbanas de las ciudades donde el sector ha concentrado sus actividades para identificar los cambios recientes y las relaciones establecidas. El uso de la herramienta SIG ser\u00e1 especialmente importante en este \u00faltimo ejercicio, y tendr\u00e1 una aplicaci\u00f3n muy relevante en todos los m\u00e9todos propuestos.\r\n\r\nLos resultados esperados son diversos. Primero, se espera m\u00e1s informaci\u00f3n y detalle sobre las relaciones entre actores claves en la provincia y el rol del sector salmonicultor globalizado. Son estas decisiones las que han significado grandes transformaciones territoriales en la provincia iniciadas durante la d\u00e9cada de 1980 y que culminan con la actual crisis debido al virus ISA. En este sentido, el a\u00f1o 2008 marca una ruptura en el desarrollo del sector. Tambi\u00e9n se espera establecer la trayectoria del grado de sustentabilidad experimentado en la provincia a trav\u00e9s de la adaptaci\u00f3n de nuevas metodolog\u00edas que ha surgido durante la \u00faltima d\u00e9cada, tales como la huella ecol\u00f3gica y el \u00cdndice de Progreso Genuino. Tomando en cuenta que un territorio es una construcci\u00f3n que vincula una sociedad o comunidad con su medio ambiente inmediato, los aspectos socio-culturales que han experimentado los residentes de la provincia son de suma importancia. A trav\u00e9s de encuestas, y las mismas entrevistas semi-estructuradas se pretende entender mejor los cambios en pr\u00e1cticas, expectativas y otros aspectos que los cambios recientes han incentivado.\r\n\r\nEste caso provincial, debido al alto impacto del sector salmonicultor en un tiempo relativamente corto, ser\u00e1 un aporte a estudios de transformaciones locales impulsadas por un sector globalizado del que surgir\u00e1n observaciones sobre la expansi\u00f3n de las actividades salmoneras a la regi\u00f3n de Ays\u00e9n. Por esta raz\u00f3n, el aporte de la investigaci\u00f3n est\u00e1 en temas de distintos niveles y en relaci\u00f3n a distintos grupos: al debate de los impactos de la globalizaci\u00f3n contempor\u00e1nea; en t\u00e9rminos de las transformaciones en la provincia y la sustentabilidad; el rol de los agentes de este sector acu\u00edcola en impulsarlas; a nivel local, en las transformaciones territoriales en los alrededores de las ciudades peque\u00f1as en la isla y la discusi\u00f3n sobre nuevas ruralidades donde actividades residenciales y comerciales cohabitan con actividades agr\u00edcolas tradicionales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2010<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Financiamiento Privado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26227\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Proyectos en convenio con Empresas Agroquimicas Chilenas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26227\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26227\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]*El valor fue calculado en base a una media del convenio que se establece con las empresas qu\u00edmicas.\r\n\r\n\u0095\tCHEMIE Chile. Eficacia de DC-MAX SL para el control de Neofabraea sp., en manzanos org\u00e1nicos en la localidad de Bulnes, Chill\u00e1n. \r\n\u0095\tANASAC. Eficacia bactericida de Cobamin para el control de Xanthomonas arboricola pv. corylina en Corylus avellana, Regi\u00f3n de La Araucan\u00eda. Chile.\r\n\u0095\tANASAC. Eficacia bactericida de Cobamin para el control de hongos de poscosecha de avellana europea, Regi\u00f3n de La Araucan\u00eda. Chile.\r\n\u0095\tCHEMIE Chile. Eficacia in vitro de DC-MAX SL para el control de Neofabraea sp.\r\n\u0095\tBasf Chile. Eficacia in vitro y in planta del producto comercial Comet EC contra Xanthomonas arboricola pv. corylina, Regi\u00f3n de La Araucan\u00eda. Chile.\r\n\u0095\tBasf Chile. Eficacia in vitro del producto comercial Comet EC contra hongos de la semilla y estructuras reproductivas del avellano europeo, Regi\u00f3n de La Araucan\u00eda. Chile.\r\n\u0095\tBASF Chile. Verificaci\u00f3n de viabilidad de cepas de bacterias antagonistas contenidas en el producto Ecoterra SC. Chile.\r\n\u0095\tBioAmerica S.A. \u0093Evaluaci\u00f3n fitot\u00f3xica in vivo del bioestimulante BC-FE-12 en ar\u00e1ndano\u0094. Chile.\r\n\u0095\tAgrotechnology. \u0093Eficacia del fungicida org\u00e1nico GWN9999 contra Botrytis cinerea en cultivares de ar\u00e1ndano\u0094. Chile\r\n\u0095\tArysta Life Science Chile. \u0093Eficacia in vivo de los fungicidas Tebuconazole y Caldera contra Neofusicoccum nonquaesitum y N. parvum en ar\u00e1ndano\u0094. Chile.\r\n\u0095\tStoller. \u0093Evaluaci\u00f3n in vivo de Sett, Stimulate and X-cyte en ar\u00e1ndano\u0094. Chile.\r\n\u0095\tMIP Agro. \u0093Eficacia in vivo de Ospobot contra Botrytis cinerea en ar\u00e1ndano\u0094. Chile.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Responsable Alterno<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> 1100975<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2010 - Marzo 2013<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"27081\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            VALIDATION OF NEUROPSYCHOLOGICAL TESTS AND BIOMARKERS FOR THE DIAGNOSIS OF MILD ALZHEIMER DISEASE\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-27081\" class=\"accordion-collapse collapse\" data-bs-parent=\"#27081\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Research project aimed at identifying neuropsychological and biological markers for the early detection of Alzheimer's disease.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2010 - Diciembre 2010<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26801\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Evoluci\u00f3n de la escritura acad\u00e9mica y\/o profesional de una cohorte de estudiantes en cuatro carreras universitarias\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26801\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26801\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1 me-2\"><i class=\"fa fa-solid fa-id-card-clip fa-fw\"><\/i> FONDEF (DO71-1003)<\/li><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2009 - Julio 2014<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Agencia Nacional de Investigaci\u00f3n y Desarrollo - ANID<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26226\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Tecnolog\u00eda sustentable para la producci\u00f3n de cerezas de exportaci\u00f3n en la zona centro-sur de Chile ( Los Angeles a Osorno).\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26226\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26226\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Particip\u00e9 en este proyecto desde el 2010 hasta el 2013.\r\n\r\nObjetivo general\r\nCrear y transferir la tecnolog\u00eda necesaria que permita la producci\u00f3n y exportaci\u00f3n a gran escala de cerezas de alta calidad en la zona Centro-Sur de Chile.\r\n\r\nObjetivos espec\u00edficos\r\nEvaluar el potencial productivo y de calidad de variedades tard\u00edas de cerezas aptas de producir en la zona centro sur.; Desarrollar las de directrices la Producci\u00f3n Integrada de Cerezas en la zona CentroSur.; Transferir y difundir, comenzando desde una fase temprana, la tecnolog\u00eda que desarrollar\u00e1 el proyecto.; Proponer el diseno de un centro tecnol\u00f3gico y de difusi\u00f3n frut\u00edcola en la zona que basado en la tecnolog\u00eda propuesta por el proyecto, realice labores de investigaci\u00f3n, desarrollo y transferencia tecnol\u00f3gica.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2009 - Diciembre 2009<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25981\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Detecci\u00f3n del virus de la anemia infecciosa del Salm\u00f3n (ISAV) y de la enfermedad pancre\u00e1tica (PDV) en peces silvestres y asilvestrados de lagos de la Regi\u00f3n de Los Lagos con concesiones de acuicultura\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25981\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25981\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #35DB54\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Marzo 2009 - Marzo 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#35DB54 !important; color:#FFF\">Finalizado<\/small><small class=\"ms-2 badge rounded-pill fw-semibold\" style=\"background-color:#F0F1F3 !important; color:#797979\"><i class=\"fa fa-solid fa-lg fa-money-check-dollar fa-fw me-1\"><\/i>Universidad de Coimbra, Portugal.<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26754\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Memoria colectiva y representaciones sociales de la identidad nacional portuguesa\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26754\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26754\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"]Materia Espec\u00edfica: Ahondar sobre los contenidos, antecedentes y consecuencias de la identidad nacional portuguesa y su relaci\u00f3n con la memoria colectiva.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2009 - Diciembre 2011<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26731\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Aprendizaje por exposici\u00f3n a est\u00edmulos: Fen\u00f3menos y mecanismos de aprendizaje perceptivo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26731\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26731\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2009 - Septiembre 2014<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26804\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Est\u00e1ndares para la ense\u00f1anza de Espa\u00f1ol como Lengua Segunda y Extranjera\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26804\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26804\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Mayo 2008 - Agosto 2011<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26805\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            La historia del Instituto de Filolog\u00eda de la Universidad de Buenos Aires. Un enfoque estrat\u00e9gico-discursivo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26805\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26805\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #EFB956\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Abril 2008 - Abril 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#EFB956 !important; color:#FFF\">Adjudicado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26895\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Muestreo, recolecci\u00f3n y uso de nematodos entomopat\u00f3genos con potencial biopesticida en el Estado Zulia\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26895\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26895\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Investigador\/a Responsable<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2004 - Diciembre 2005<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25982\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Investigaci\u00f3n, Tecnolog\u00edas de la Informaci\u00f3n y Capacitaci\u00f3n Local para apoyar la Toma de Decisiones sanitarias en Mareas Rojas\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25982\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25982\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2004 - Diciembre 2007<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26806\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            El discurso del Instituto de Filolog\u00eda y Literaturas Hisp\u00e1nicas \u0091Dr. Amado Alonso\u0092: un enfoque estrat\u00e9gico discursivo\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26806\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26806\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2003 - Diciembre 2004<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"25983\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            An\u00e1lisis de riesgos de la operaci\u00f3n de viveros flotantes y barcos de transporte de peces vivos de salm\u00f3nidos\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-25983\" class=\"accordion-collapse collapse\" data-bs-parent=\"#25983\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #03286B\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 ms-1\"><i class=\"fa fa-regular fa-calendar fa-fw ms-1\"><\/i>Enero 2000 - Diciembre 2003<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\"><small class=\"badge rounded-pill fw-semibold\" style=\"background-color:#03286B !important; color:#FFF\">Ejecutado<\/small>\n                            <div class=\"accordion accordion-flush\" id=\"26807\">\n                                <div class=\"accordion-item\">\n                                    <h3 class=\"my-0 small-space pt-2 title-ss text-decoration-none accordion-header\">\n                                        <a role=\"button\" class=\"bg-transparent p-0\" href=\"\">\n                                            <i class=\"fas fa-solid fa-link fa-fw me-2\"><\/i>\n                                            Heterogeneidad y homogeneidad del espa\u00f1ol en la Argentina: representaciones sociales, modelos y variaci\u00f3n\n                                        <\/a><\/h3>\n                                    <div id=\"collapse-26807\" class=\"accordion-collapse collapse\" data-bs-parent=\"#26807\">\n                                        <div class=\"accordion-body p-0 pt-4 pb-4\">\n                                            [vc_section el_class=\"container mx-auto align-items-center circle--pattern\" css=\".vc_custom_1648956589196{padding-top: 3rem !important;}\"][vc_row el_class=\"pb-5\"][vc_column][vc_wp_custommenu nav_menu=\"6\"][uoh_breadcrumb_component automatic_breadcrumb=\"true\"][uoh_title_component title_dropdown=\"big\" title_decorator=\"true\"]{{title}}[\/uoh_title_component][vc_column_text css=\"\"][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649209804184{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5\"][vc_row el_class=\"container mx-auto align-items-center p-md-0 pt-5\"][vc_column el_class=\"p-0\"][\/vc_column][\/vc_row][\/vc_section][vc_section css=\".vc_custom_1649210787516{background-color: #f6faff !important;}\" el_class=\"p-md-0 pt-md-5 pb-md-5\"][vc_row el_class=\"container mx-auto align-items-center\"][vc_column][\/vc_column][\/vc_row][\/vc_section]\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div><div class=\"mt-3\"><i class=\"fas fa-solid fa-user-tag fa-fw me-2\"><\/i><small class=\"text-muted\">Co-Investigador\/a<\/small><\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>[\/vc_tta_section][vc_tta_section title=&#8221;Libros y Monografias&#8221; tab_id=&#8221;libros&#8221;]<link rel=\"stylesheet\" id=\"font-awesome-css\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.5.1\/css\/all.min.css\" type=\"text\/css\" media=\"all\"><div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0 px-md-0 \"><\/div><\/div>[\/vc_tta_section][vc_tta_section title=&#8221;Cap\u00edtulos de Libros&#8221; tab_id=&#8221;cap-libros&#8221;]<link rel=\"stylesheet\" id=\"font-awesome-css\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.5.1\/css\/all.min.css\" type=\"text\/css\" media=\"all\"><div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0 px-md-0 \"><\/div><\/div>[\/vc_tta_section][vc_tta_section title=&#8221;Contacto&#8221; tab_id=&#8221;contacto&#8221;][\/vc_tta_section][\/vc_tta_tabs][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"featured_media":20018,"parent":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"institute_academics":[7],"profile_academics":[14],"class_list":["post-781","academics","type-academics","status-publish","has-post-thumbnail","hentry","institute_academics-instituto-de-ciencias-de-la-educacion","profile_academics-academico"],"rut_academico":"13293897-0","mail_academico":"jose.mela@uoh.cl","n_proyectos":"16","n_publicaciones":"10","n_libros":"1","n_cap_libros":"8","n_otros_libros":"0","acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jos\u00e9 Mela - Investigaci\u00f3n<\/title>\n<meta name=\"description\" content=\"Profesor Asociado del Instituto de Ciencias de la Educaci\u00f3n de la Universidad Estatal de O&#039;Higgins.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uoh.cl\/investigacion\/academico\/jose-mela\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jos\u00e9 Mela - Investigaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Profesor Asociado del Instituto de Ciencias de la Educaci\u00f3n de la Universidad Estatal de O&#039;Higgins.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/investigacion\/academico\/jose-mela\/\" \/>\n<meta property=\"og:site_name\" content=\"Investigaci\u00f3n\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T23:02:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2022\/04\/Jose-Mela-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/academico\/jose-mela\/\",\"url\":\"https:\/\/www.uoh.cl\/investigacion\/academico\/jose-mela\/\",\"name\":\"Jos\u00e9 Mela - Investigaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/academico\/jose-mela\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/academico\/jose-mela\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2022\/04\/Jose-Mela-1.jpg\",\"datePublished\":\"2022-04-29T16:48:19+00:00\",\"dateModified\":\"2026-05-12T23:02:31+00:00\",\"description\":\"Profesor Asociado del Instituto de Ciencias de la Educaci\u00f3n de la Universidad Estatal de O'Higgins.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/academico\/jose-mela\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uoh.cl\/investigacion\/academico\/jose-mela\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/academico\/jose-mela\/#primaryimage\",\"url\":\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2022\/04\/Jose-Mela-1.jpg\",\"contentUrl\":\"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2022\/04\/Jose-Mela-1.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/academico\/jose-mela\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Acad\u00e9micos\",\"item\":\"https:\/\/www.uoh.cl\/investigacion\/academico\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jos\u00e9 Mela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uoh.cl\/investigacion\/#website\",\"url\":\"https:\/\/www.uoh.cl\/investigacion\/\",\"name\":\"Investigaci\u00f3n\",\"description\":\"Sitio web de investigaci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uoh.cl\/investigacion\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jos\u00e9 Mela - Investigaci\u00f3n","description":"Profesor Asociado del Instituto de Ciencias de la Educaci\u00f3n de la Universidad Estatal de O'Higgins.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uoh.cl\/investigacion\/academico\/jose-mela\/","og_locale":"es_ES","og_type":"article","og_title":"Jos\u00e9 Mela - Investigaci\u00f3n","og_description":"Profesor Asociado del Instituto de Ciencias de la Educaci\u00f3n de la Universidad Estatal de O'Higgins.","og_url":"https:\/\/www.uoh.cl\/investigacion\/academico\/jose-mela\/","og_site_name":"Investigaci\u00f3n","article_modified_time":"2026-05-12T23:02:31+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2022\/04\/Jose-Mela-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/investigacion\/academico\/jose-mela\/","url":"https:\/\/www.uoh.cl\/investigacion\/academico\/jose-mela\/","name":"Jos\u00e9 Mela - Investigaci\u00f3n","isPartOf":{"@id":"https:\/\/www.uoh.cl\/investigacion\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uoh.cl\/investigacion\/academico\/jose-mela\/#primaryimage"},"image":{"@id":"https:\/\/www.uoh.cl\/investigacion\/academico\/jose-mela\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2022\/04\/Jose-Mela-1.jpg","datePublished":"2022-04-29T16:48:19+00:00","dateModified":"2026-05-12T23:02:31+00:00","description":"Profesor Asociado del Instituto de Ciencias de la Educaci\u00f3n de la Universidad Estatal de O'Higgins.","breadcrumb":{"@id":"https:\/\/www.uoh.cl\/investigacion\/academico\/jose-mela\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/investigacion\/academico\/jose-mela\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/investigacion\/academico\/jose-mela\/#primaryimage","url":"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2022\/04\/Jose-Mela-1.jpg","contentUrl":"https:\/\/www.uoh.cl\/investigacion\/wp-content\/uploads\/sites\/12\/2022\/04\/Jose-Mela-1.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.uoh.cl\/investigacion\/academico\/jose-mela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Acad\u00e9micos","item":"https:\/\/www.uoh.cl\/investigacion\/academico\/"},{"@type":"ListItem","position":2,"name":"Jos\u00e9 Mela"}]},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/investigacion\/#website","url":"https:\/\/www.uoh.cl\/investigacion\/","name":"Investigaci\u00f3n","description":"Sitio web de investigaci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/investigacion\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/academics\/781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/academics"}],"about":[{"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/types\/academics"}],"version-history":[{"count":18,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/academics\/781\/revisions"}],"predecessor-version":[{"id":24659,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/academics\/781\/revisions\/24659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/media\/20018"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/media?parent=781"}],"wp:term":[{"taxonomy":"institute_academics","embeddable":true,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/institute_academics?post=781"},{"taxonomy":"profile_academics","embeddable":true,"href":"https:\/\/www.uoh.cl\/investigacion\/wp-json\/wp\/v2\/profile_academics?post=781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}