
{"id":4398,"date":"2026-03-27T14:59:11","date_gmt":"2026-03-27T17:59:11","guid":{"rendered":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/2026\/03\/27\/gobernanza-del-riesgo-uoh-realiza-seminario-sobre-gestion-de-desastres-con-enfoque-interdisciplinario\/"},"modified":"2026-03-27T14:59:11","modified_gmt":"2026-03-27T17:59:11","slug":"gobernanza-del-riesgo-uoh-realiza-seminario-sobre-gestion-de-desastres-con-enfoque-interdisciplinario","status":"publish","type":"post","link":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/2026\/03\/27\/gobernanza-del-riesgo-uoh-realiza-seminario-sobre-gestion-de-desastres-con-enfoque-interdisciplinario\/","title":{"rendered":"Gobernanza del riesgo: UOH realiza seminario sobre gesti\u00f3n de desastres con enfoque interdisciplinario"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row][vc_column]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\"><span itemprop=\"name\">Instituto de Ciencias Sociales<\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/noticias\/\"><span itemprop=\"name\">Noticias<\/span><\/a><meta itemprop=\"position\" content=\"3\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Gobernanza del riesgo: UOH realiza seminario sobre gesti\u00f3n de desastres <\/span><meta itemprop=\"position\" content=\"4\" \/><\/ol><\/div><ul class=\"p-0 list-style-none d-inline-block\"><li class=\"p-0\"><a href=https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/category\/ciencias-sociales\/ class=\"px-1 py-2\">Ciencias Sociales<\/a><\/li><\/ul><div class=\"date_publish_post\"> \u25cf Vie 27 de Marzo 2026<\/div><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block title--decorator  big\">Gobernanza del riesgo: UOH realiza seminario sobre gesti\u00f3n de desastres con enfoque interdisciplinario<\/h1><\/div>[vc_row_inner el_class=&#8221;border-separator m-0&#8243;][vc_column_inner width=&#8221;2\/3&#8243;]<div class=\"author_wp_class\"> Escrito por <span>Universidad de O'Higgins<\/span><\/div>[\/vc_column_inner][vc_column_inner el_class=&#8221;align-items-end-publish&#8221; width=&#8221;1\/3&#8243;]<div class=\"uoh_social_network_component uoh_row col-12 justify-content-end m-0 p-0\"> <div class=\"icon__facebook-share-button\">\n                       <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/2026\/03\/27\/gobernanza-del-riesgo-uoh-realiza-seminario-sobre-gestion-de-desastres-con-enfoque-interdisciplinario\/\" target=\"_blank\"> <div class=\"icon__facebook-svg\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22.4px\" height=\"48.3px\" viewBox=\"0 0 22.4 48.3\" style=\"overflow:visible;enable-background:new 0 0 22.4 48.3;\" xml:space=\"preserve\">\n                <defs>\n                <\/defs>\n                <path class=\"st0\" d=\"M22.4,15.6h-7.6v-5c0-1.9,1.2-2.3,2.1-2.3c0.9,0,5.4,0,5.4,0V0l-7.4,0C6.6,0,4.8,6.2,4.8,10.1v5.5H0v8.5h4.8\n                    c0,10.9,0,24.1,0,24.1h10c0,0,0-13.3,0-24.1h6.8L22.4,15.6z\"><\/path>\n                <\/svg><\/a><\/div>\n                    <\/div><div class=\"icon__twitter-share-button\">\n                        <div class=\"icon__twitter-svg\"><a target=\"_blank\" href=\"http:\/\/twitter.com\/share?url=https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/2026\/03\/27\/gobernanza-del-riesgo-uoh-realiza-seminario-sobre-gestion-de-desastres-con-enfoque-interdisciplinario\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/a><\/div>\n                        <\/div><div class=\"icon__linkedin-share-button\">\n                        <div class=\"icon__linkedin-svg\">\n                        <a target=\"__blank\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/2026\/03\/27\/gobernanza-del-riesgo-uoh-realiza-seminario-sobre-gestion-de-desastres-con-enfoque-interdisciplinario\/\"><svg enable-background=\"new 0 0 100 100\" height=\"100px\" id=\"Layer_1\" version=\"1.1\" viewBox=\"0 0 100 100\" width=\"100px\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><circle cx=\"50\" cy=\"50\" fill=\"#ccc\" r=\"45\"\/><g id=\"LinkedIn_1_\"><rect fill=\"#FFFFFF\" height=\"24.361\" width=\"7.69\" x=\"31.271\" y=\"43.569\"\/><path d=\"M59.968,43.334c-4.406,0-7.165,2.387-7.677,4.058v-3.823h-8.636c0.109,2.03,0,24.361,0,24.361h8.636    V54.748c0-0.733-0.034-1.465,0.19-1.991c0.594-1.464,1.869-2.985,4.162-2.985c2.998,0,4.361,2.253,4.361,5.552V67.93h8.721V54.384    C69.726,46.839,65.432,43.334,59.968,43.334z\" fill=\"#FFFFFF\"\/><path d=\"M34.973,32.069c-2.839,0-4.696,1.823-4.696,4.229c0,2.361,1.804,4.224,4.589,4.224h0.054    c2.891,0,4.69-1.869,4.69-4.229C39.555,33.888,37.81,32.069,34.973,32.069z\" fill=\"#FFFFFF\"\/><\/g><\/g><\/svg><\/a><\/div>\n\n            <\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_single_image image=&#8221;74837&#8243; img_size=&#8221;1500&#215;1000&#8243; add_caption=&#8221;yes&#8221; alignment=&#8221;center&#8221; onclick=&#8221;img_link_large&#8221; css=&#8221;&#8221;][vc_column_text]\u00a0[\/vc_column_text][vc_column_text css=&#8221;&#8221;]<\/p>\n<ul>\n<li><em>El encuentro de car\u00e1cter h\u00edbrido convoc\u00f3 a expertos internacionales, instituciones p\u00fablicas, academia y entidades municipales en aras de fortalecer capacidades locales ante escenarios de amenaza. <\/em><\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_column_text]\u00a0[\/vc_column_text][vc_column_text css=&#8221;&#8221;]La <a href=\"https:\/\/www.uoh.cl\/\">Universidad de O\u2019Higgins<\/a> (UOH) realiz\u00f3 el <strong>seminario \u201cExperiencias y Herramientas para la Gobernanza Territorial del Riesgo de Desastres\u201d<\/strong>, generando un espacio de articulaci\u00f3n entre investigaci\u00f3n aplicada y experiencias institucionales orientadas a anticipar escenarios cr\u00edticos. La jornada se desarroll\u00f3 en el marco del proyecto ANID FOVI240153 \u201cTerritorios y Gobernanza del Riesgo: fortaleciendo la interdisciplina para prevenir desastres socio-naturales\u201d, que busca abordar problem\u00e1ticas complejas desde la mirada global de la Regi\u00f3n.<\/p>\n<p>El responsable del proyecto y acad\u00e9mico del <a href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/\">Instituto de Ciencias Sociales<\/a>, <a href=\"https:\/\/www.uoh.cl\/investigacion\/academico\/ricardo-fuentealba\/\">Ricardo Fuentealba<\/a>, explic\u00f3 que la actividad permiti\u00f3 exponer avances del proyecto, junto con aportes internacionales ofrecidos por el profesor Kees Boersma, de la Universidad Libre de \u00c1msterdam, y aprendizajes locales como la experiencia de la Municipalidad de Pudahuel, reconocida como Nodo de Resiliencia por la Oficina de las Naciones Unidas para la Reducci\u00f3n del Riesgo de Desastres (UNDRR), evidenciando la relevancia de integrar conocimientos diversos.<\/p>\n<p>Mencion\u00f3 que este seminario plantea la necesidad de avanzar hacia enfoques preventivos sostenidos, considerando los cambios normativos recientes y las brechas existentes en su aplicaci\u00f3n a nivel regional y local. \u201cEsta jornada busc\u00f3 abrir una reflexi\u00f3n profunda sobre c\u00f3mo estamos enfrentando estos fen\u00f3menos. Si bien la Ley 21.364 marca un progreso significativo en materia institucional sustituyendo la antigua ONEMI por SENAPRED, su implementaci\u00f3n a\u00fan enfrenta desaf\u00edos importantes fuera del nivel central\u201d, siendo esto una tarea urgente por resolver subray\u00f3 el acad\u00e9mico.[\/vc_column_text][vc_zigzag color=&#8221;white&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;74839&#8243; img_size=&#8221;700&#215;450&#8243; onclick=&#8221;link_image&#8221; css=&#8221;&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;74838&#8243; img_size=&#8221;700&#215;450&#8243; onclick=&#8221;link_image&#8221; css=&#8221;&#8221;][\/vc_column_inner][\/vc_row_inner][vc_zigzag color=&#8221;white&#8221;][vc_column_text css=&#8221;&#8221;]<\/p>\n<h4><strong>Aprendizajes compartidos<\/strong><\/h4>\n<p>El Doctor en Ciencias Sociales se\u00f1al\u00f3 que el seminario tambi\u00e9n plante\u00f3 la importancia de incorporar pr\u00e1cticas permanentes de anticipaci\u00f3n, as\u00ed como fortalecer v\u00ednculos entre actores para mejorar la capacidad de respuesta y adaptaci\u00f3n frente a escenarios cada vez m\u00e1s complejos. \u201cY en ese sentido, la idea es transitar desde un enfoque reactivo a uno preventivo, basado en acciones cotidianas de reducci\u00f3n del riesgo, como las que ya se implementan en los Pa\u00edses Bajos o en Pudahuel\u201d, agreg\u00f3 el experto.<\/p>\n<p>Respecto a los redes de articulaci\u00f3n, Fuentealba destac\u00f3 que la jornada desarrollada en formato h\u00edbrido, logr\u00f3 convocar representantes de la Direcci\u00f3n Regional del Servicio Nacional de Prevenci\u00f3n y Respuesta ante Desastres (SENAPRED) O\u2019Higgins, Consejo de Monumentos Nacionales, Cruz Roja, FOSIS y de municipios como Rancagua, Palmilla, Litueche, entre otras organizaciones y servicios p\u00fablicos. Todo esto contribuye directamente a cumplir con parte de los objetivos que persigue el proyecto ANID FOVI240153\u201d.<\/p>\n<h4><strong>Retroalimentaci\u00f3n<\/strong><\/h4>\n<p>Adem\u00e1s del seminario, el equipo del proyecto FOVI visit\u00f3 la nueva sede de SENAPRED regional, donde conocieron la Unidad de Alerta Temprana (UAT), encargada de monitorear amenazas naturales en la regi\u00f3n. Dicha actividad fue valorada por la acad\u00e9mica de la Facultad de Gobierno y directora de CITRID de la Universidad de Chile, Paulina Vergara, quien es adem\u00e1s investigadora asociada al proyecto FOVI y coorganizadora del seminario. \u201cRecorrer SENAPRED O\u2019Higgins permite dimensionar los avances en la capacidad estatal para enfrentar eventos adversos. La reorganizaci\u00f3n del servicio y su \u00e9nfasis en el trabajo coordinado resultan fundamentales para responder a m\u00faltiples amenazas. Este tipo de articulaci\u00f3n interinstitucional fortalece la respuesta ante contingencias y proyecta acciones sostenidas que mejoran las posibilidades de la regi\u00f3n de salir adelante en caso de una emergencia y de reducir el riesgo de desastre a largo plazo\u201d, concluy\u00f3 Vergara, haciendo una menci\u00f3n especial al desarrollo del seminario y a sus actividades de retroalimentaci\u00f3n.[\/vc_column_text][vc_zigzag color=&#8221;white&#8221;][vc_single_image image=&#8221;74840&#8243; img_size=&#8221;large&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; css=&#8221;&#8221;][vc_zigzag color=&#8221;white&#8221;][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650255686594{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center p-md-0 pt-5 pb-5&#8243;][vc_column el_class=&#8221;pb-5&#8243;][vc_row_inner el_class=&#8221;pb-5&#8243;][vc_column_inner]<div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0\"><h2 class=\"title title--decorator title--ms d-inline-block\">Te Recomendamos<\/h2><\/div><\/div><div class=\"content-holder\"><div class=\"row  swipper-news-list not--activate-hack \"><div class=\"row -wrapper\"><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/category\/investigacion\/\">\n                                        Investigaci\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/wp-content\/uploads\/sites\/29\/2026\/04\/FWIS2026-web-op.jpg\" alt=\"Comienza proceso de postulaciones al Premio For Women in Science 2026\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/444;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Jueves 30, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/2026\/04\/30\/comienza-proceso-de-postulaciones-al-premio-for-women-in-science-2026\/\">\n                                    <h3 class=\"small-space\">Comienza proceso de postulaciones al Premio For Women in Science 2026<\/h3><\/a>\n\n                                    <p>La convocatoria, abierta entre el 22 de abril y el 28 de mayo de 2026, busca impulsar la trayectoria y aporte cient\u00edfico de investigadoras chilenas.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/2026\/04\/30\/comienza-proceso-de-postulaciones-al-premio-for-women-in-science-2026\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/category\/investigacion\/\">\n                                        Investigaci\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/wp-content\/uploads\/sites\/29\/2026\/04\/Dia-de-la-Propiedad-Intelectual.jpg\" alt=\"UOH conmemora D\u00eda Mundial de la Propiedad Intelectual destacando avances en protecci\u00f3n\" style=\"--smush-placeholder-width: 2419px; --smush-placeholder-aspect-ratio: 2419\/1609;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Jueves 30, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/2026\/04\/30\/uoh-conmemora-dia-mundial-de-la-propiedad-intelectual-destacando-avances-en-proteccion\/\">\n                                    <h3 class=\"small-space\">UOH conmemora D\u00eda Mundial de la Propiedad Intelectual destacando avances en protecci\u00f3n<\/h3><\/a>\n\n                                    <p>La Direcci\u00f3n de Transferencia e Innovaci\u00f3n ha apoyado la protecci\u00f3n de 21 resultados de investigaci\u00f3n, concretado 11 solicitudes de patente, 12 registros de derechos de autor y 1 marca comercial.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/2026\/04\/30\/uoh-conmemora-dia-mundial-de-la-propiedad-intelectual-destacando-avances-en-proteccion\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/wp-content\/uploads\/sites\/29\/2026\/04\/Inauguracion-Ano-Academico-2026-6.jpg\" alt=\"Reflexi\u00f3n universitaria: UOH inaugura A\u00f1o Acad\u00e9mico 2026 pensando en los desaf\u00edos de la Educaci\u00f3n Superior\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Mi\u00e9rcoles 29, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/2026\/04\/29\/reflexion-universitaria-uoh-inaugura-ano-academico-2026-pensando-en-los-desafios-de-la-educacion-superior\/\">\n                                    <h3 class=\"small-space\">Reflexi\u00f3n universitaria: UOH inaugura A\u00f1o Acad\u00e9mico 2026 pensando en los desaf\u00edos de la Educaci\u00f3n Superior<\/h3><\/a>\n\n                                    <p>La ceremonia promovi\u00f3 el an\u00e1lisis acerca de los cambios educativos que se avecinan dentro de los procesos de formaci\u00f3n universitaria ajustados a contextos digitales.   <\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/2026\/04\/29\/reflexion-universitaria-uoh-inaugura-ano-academico-2026-pensando-en-los-desafios-de-la-educacion-superior\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pagination justify-content-center my-5\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/wp-json\/wp\/v2\/posts\/4398\/\/page\/2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/wp-json\/wp\/v2\/posts\/4398\/\/page\/3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/wp-json\/wp\/v2\/posts\/4398\/\/page\/103\">103<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/wp-json\/wp\/v2\/posts\/4398\/\/page\/2\"><div class=\"icon-pagination-next\"> <?xml version=\"1.0\" ?><svg viewBox=\"0 0 96 96\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><title\/><path d=\"M39.3756,48.0022l30.47-25.39a6.0035,6.0035,0,0,0-7.6878-9.223L26.1563,43.3906a6.0092,6.0092,0,0,0,0,9.2231L62.1578,82.615a6.0035,6.0035,0,0,0,7.6878-9.2231Z\"\/><\/svg> <\/div><\/a><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>El encuentro de car\u00e1cter h\u00edbrido convoc\u00f3 a expertos internacionales, instituciones p\u00fablicas, academia y entidades municipales en aras de fortalecer capacidades locales ante escenarios de amenaza. <\/p>\n","protected":false},"author":34,"featured_media":4399,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[29],"tags":[],"class_list":["post-4398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencias-sociales"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gobernanza del riesgo: UOH realiza seminario sobre gesti\u00f3n de desastres con enfoque interdisciplinario - Instituto de Ciencias Sociales<\/title>\n<meta name=\"description\" content=\"El encuentro de car\u00e1cter h\u00edbrido convoc\u00f3 a expertos internacionales, instituciones p\u00fablicas, academia y entidades municipales en aras de fortalecer capacidades locales ante escenarios de amenaza.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobernanza del riesgo: UOH realiza seminario sobre gesti\u00f3n de desastres con enfoque interdisciplinario - Instituto de Ciencias Sociales\" \/>\n<meta property=\"og:description\" content=\"El encuentro de car\u00e1cter h\u00edbrido convoc\u00f3 a expertos internacionales, instituciones p\u00fablicas, academia y entidades municipales en aras de fortalecer capacidades locales ante escenarios de amenaza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/2026\/03\/27\/gobernanza-del-riesgo-uoh-realiza-seminario-sobre-gestion-de-desastres-con-enfoque-interdisciplinario\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto de Ciencias Sociales\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-27T17:59:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/wp-content\/uploads\/sites\/29\/2026\/03\/Foto-seminario-4.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Universidad de O&#039;Higgins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Universidad de O&#039;Higgins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/2026\/03\/27\/gobernanza-del-riesgo-uoh-realiza-seminario-sobre-gestion-de-desastres-con-enfoque-interdisciplinario\/\",\"url\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/2026\/03\/27\/gobernanza-del-riesgo-uoh-realiza-seminario-sobre-gestion-de-desastres-con-enfoque-interdisciplinario\/\",\"name\":\"Gobernanza del riesgo: UOH realiza seminario sobre gesti\u00f3n de desastres con enfoque interdisciplinario - Instituto de Ciencias Sociales\",\"isPartOf\":{\"@id\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/2026\/03\/27\/gobernanza-del-riesgo-uoh-realiza-seminario-sobre-gestion-de-desastres-con-enfoque-interdisciplinario\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/2026\/03\/27\/gobernanza-del-riesgo-uoh-realiza-seminario-sobre-gestion-de-desastres-con-enfoque-interdisciplinario\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/wp-content\/uploads\/sites\/29\/2026\/03\/Foto-seminario-4.jpeg\",\"datePublished\":\"2026-03-27T17:59:11+00:00\",\"author\":{\"@id\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"description\":\"El encuentro de car\u00e1cter h\u00edbrido convoc\u00f3 a expertos internacionales, instituciones p\u00fablicas, academia y entidades municipales en aras de fortalecer capacidades locales ante escenarios de amenaza.\",\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/2026\/03\/27\/gobernanza-del-riesgo-uoh-realiza-seminario-sobre-gestion-de-desastres-con-enfoque-interdisciplinario\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/2026\/03\/27\/gobernanza-del-riesgo-uoh-realiza-seminario-sobre-gestion-de-desastres-con-enfoque-interdisciplinario\/#primaryimage\",\"url\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/wp-content\/uploads\/sites\/29\/2026\/03\/Foto-seminario-4.jpeg\",\"contentUrl\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/wp-content\/uploads\/sites\/29\/2026\/03\/Foto-seminario-4.jpeg\",\"width\":1280,\"height\":960},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/#website\",\"url\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/\",\"name\":\"Instituto de Ciencias Sociales\",\"description\":\"Otro sitio de Sitios de Universidad O'higgins\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\",\"name\":\"Universidad de O'Higgins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"caption\":\"Universidad de O'Higgins\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gobernanza del riesgo: UOH realiza seminario sobre gesti\u00f3n de desastres con enfoque interdisciplinario - Instituto de Ciencias Sociales","description":"El encuentro de car\u00e1cter h\u00edbrido convoc\u00f3 a expertos internacionales, instituciones p\u00fablicas, academia y entidades municipales en aras de fortalecer capacidades locales ante escenarios de amenaza.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Gobernanza del riesgo: UOH realiza seminario sobre gesti\u00f3n de desastres con enfoque interdisciplinario - Instituto de Ciencias Sociales","og_description":"El encuentro de car\u00e1cter h\u00edbrido convoc\u00f3 a expertos internacionales, instituciones p\u00fablicas, academia y entidades municipales en aras de fortalecer capacidades locales ante escenarios de amenaza.","og_url":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/2026\/03\/27\/gobernanza-del-riesgo-uoh-realiza-seminario-sobre-gestion-de-desastres-con-enfoque-interdisciplinario\/","og_site_name":"Instituto de Ciencias Sociales","article_published_time":"2026-03-27T17:59:11+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/wp-content\/uploads\/sites\/29\/2026\/03\/Foto-seminario-4.jpeg","type":"image\/jpeg"}],"author":"Universidad de O'Higgins","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Universidad de O'Higgins","Tiempo estimado de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/2026\/03\/27\/gobernanza-del-riesgo-uoh-realiza-seminario-sobre-gestion-de-desastres-con-enfoque-interdisciplinario\/","url":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/2026\/03\/27\/gobernanza-del-riesgo-uoh-realiza-seminario-sobre-gestion-de-desastres-con-enfoque-interdisciplinario\/","name":"Gobernanza del riesgo: UOH realiza seminario sobre gesti\u00f3n de desastres con enfoque interdisciplinario - Instituto de Ciencias Sociales","isPartOf":{"@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/2026\/03\/27\/gobernanza-del-riesgo-uoh-realiza-seminario-sobre-gestion-de-desastres-con-enfoque-interdisciplinario\/#primaryimage"},"image":{"@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/2026\/03\/27\/gobernanza-del-riesgo-uoh-realiza-seminario-sobre-gestion-de-desastres-con-enfoque-interdisciplinario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/wp-content\/uploads\/sites\/29\/2026\/03\/Foto-seminario-4.jpeg","datePublished":"2026-03-27T17:59:11+00:00","author":{"@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"description":"El encuentro de car\u00e1cter h\u00edbrido convoc\u00f3 a expertos internacionales, instituciones p\u00fablicas, academia y entidades municipales en aras de fortalecer capacidades locales ante escenarios de amenaza.","inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/2026\/03\/27\/gobernanza-del-riesgo-uoh-realiza-seminario-sobre-gestion-de-desastres-con-enfoque-interdisciplinario\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/2026\/03\/27\/gobernanza-del-riesgo-uoh-realiza-seminario-sobre-gestion-de-desastres-con-enfoque-interdisciplinario\/#primaryimage","url":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/wp-content\/uploads\/sites\/29\/2026\/03\/Foto-seminario-4.jpeg","contentUrl":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/wp-content\/uploads\/sites\/29\/2026\/03\/Foto-seminario-4.jpeg","width":1280,"height":960},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/#website","url":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/","name":"Instituto de Ciencias Sociales","description":"Otro sitio de Sitios de Universidad O'higgins","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f","name":"Universidad de O'Higgins","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","caption":"Universidad de O'Higgins"}}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/wp-json\/wp\/v2\/posts\/4398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/wp-json\/wp\/v2\/comments?post=4398"}],"version-history":[{"count":0,"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/wp-json\/wp\/v2\/posts\/4398\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/wp-json\/wp\/v2\/media\/4399"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/wp-json\/wp\/v2\/media?parent=4398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/wp-json\/wp\/v2\/categories?post=4398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-sociales\/wp-json\/wp\/v2\/tags?post=4398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}