
{"id":2105,"date":"2022-09-29T09:28:16","date_gmt":"2022-09-29T12:28:16","guid":{"rendered":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/2022\/09\/29\/experto-uoh-expondra-proyecto-que-crea-primer-observatorio-de-contaminacion-del-aire-de-ohiggins\/"},"modified":"2022-09-29T09:40:28","modified_gmt":"2022-09-29T12:40:28","slug":"experto-uoh-expondra-proyecto-que-crea-primer-observatorio-de-contaminacion-del-aire-de-ohiggins","status":"publish","type":"post","link":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/2022\/09\/29\/experto-uoh-expondra-proyecto-que-crea-primer-observatorio-de-contaminacion-del-aire-de-ohiggins\/","title":{"rendered":"Experto UOH expondr\u00e1 proyecto que crea primer Observatorio de Contaminaci\u00f3n del Aire de O\u2019Higgins"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center text-right circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row][vc_column]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\"><span itemprop=\"name\">Instituto de Ciencias de la Ingenier\u00eda <\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/noticias\/\"><span itemprop=\"name\">Noticias<\/span><\/a><meta itemprop=\"position\" content=\"3\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Experto UOH expondr\u00e1 proyecto que crea primer Observatorio de Contaminaci\u00f3n <\/span><meta itemprop=\"position\" content=\"4\" \/><\/ol><\/div><ul class=\"p-0 list-style-none d-inline-block\"><li class=\"p-0\"><a href=https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/category\/ingenieria-uoh\/ class=\"px-1 py-2\">Ingenier\u00eda UOH<\/a><\/li><\/ul><div class=\"date_publish_post\"> \u25cf Jue 29 de Septiembre 2022<\/div><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block title--decorator  big\">Experto UOH expondr\u00e1 proyecto que crea primer Observatorio de Contaminaci\u00f3n del Aire de O\u2019Higgins<\/h1><\/div>[vc_row_inner el_class=&#8221;border-separator m-0&#8243;][vc_column_inner width=&#8221;2\/3&#8243;]<div class=\"author_wp_class\"> Escrito por <span>Universidad de O'Higgins<\/span><\/div>[\/vc_column_inner][vc_column_inner el_class=&#8221;align-items-end-publish&#8221; width=&#8221;1\/3&#8243;]<div class=\"uoh_social_network_component uoh_row col-12 justify-content-end m-0 p-0\"> <div class=\"icon__facebook-share-button\">\n                       <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/2022\/09\/29\/experto-uoh-expondra-proyecto-que-crea-primer-observatorio-de-contaminacion-del-aire-de-ohiggins\/\" target=\"_blank\"> <div class=\"icon__facebook-svg\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22.4px\" height=\"48.3px\" viewBox=\"0 0 22.4 48.3\" style=\"overflow:visible;enable-background:new 0 0 22.4 48.3;\" xml:space=\"preserve\">\n                <defs>\n                <\/defs>\n                <path class=\"st0\" d=\"M22.4,15.6h-7.6v-5c0-1.9,1.2-2.3,2.1-2.3c0.9,0,5.4,0,5.4,0V0l-7.4,0C6.6,0,4.8,6.2,4.8,10.1v5.5H0v8.5h4.8\n                    c0,10.9,0,24.1,0,24.1h10c0,0,0-13.3,0-24.1h6.8L22.4,15.6z\"><\/path>\n                <\/svg><\/a><\/div>\n                    <\/div><div class=\"icon__twitter-share-button\">\n                        <div class=\"icon__twitter-svg\"><a target=\"_blank\" href=\"http:\/\/twitter.com\/share?url=https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/2022\/09\/29\/experto-uoh-expondra-proyecto-que-crea-primer-observatorio-de-contaminacion-del-aire-de-ohiggins\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/a><\/div>\n                        <\/div><div class=\"icon__linkedin-share-button\">\n                        <div class=\"icon__linkedin-svg\">\n                        <a target=\"__blank\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/2022\/09\/29\/experto-uoh-expondra-proyecto-que-crea-primer-observatorio-de-contaminacion-del-aire-de-ohiggins\/\"><svg enable-background=\"new 0 0 100 100\" height=\"100px\" id=\"Layer_1\" version=\"1.1\" viewBox=\"0 0 100 100\" width=\"100px\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><circle cx=\"50\" cy=\"50\" fill=\"#ccc\" r=\"45\"\/><g id=\"LinkedIn_1_\"><rect fill=\"#FFFFFF\" height=\"24.361\" width=\"7.69\" x=\"31.271\" y=\"43.569\"\/><path d=\"M59.968,43.334c-4.406,0-7.165,2.387-7.677,4.058v-3.823h-8.636c0.109,2.03,0,24.361,0,24.361h8.636    V54.748c0-0.733-0.034-1.465,0.19-1.991c0.594-1.464,1.869-2.985,4.162-2.985c2.998,0,4.361,2.253,4.361,5.552V67.93h8.721V54.384    C69.726,46.839,65.432,43.334,59.968,43.334z\" fill=\"#FFFFFF\"\/><path d=\"M34.973,32.069c-2.839,0-4.696,1.823-4.696,4.229c0,2.361,1.804,4.224,4.589,4.224h0.054    c2.891,0,4.69-1.869,4.69-4.229C39.555,33.888,37.81,32.069,34.973,32.069z\" fill=\"#FFFFFF\"\/><\/g><\/g><\/svg><\/a><\/div>\n\n            <\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_single_image image=&#8221;10881&#8243; img_size=&#8221;large&#8221;][vc_column_text]\u00a0[\/vc_column_text][vc_column_text]<i><span lang=\"ES-MX\">Seg\u00fan explica el acad\u00e9mico del Instituto de Ciencias de la Ingenier\u00eda, Ra\u00fal Valenzuela, el objetivo es avanzar en el monitoreo, mediciones y modelamiento num\u00e9rico de la contaminaci\u00f3n y poner a disposici\u00f3n de la regi\u00f3n mayor informaci\u00f3n y una gama amplia de datos para la toma de decisiones.<\/span><\/i>[\/vc_column_text][vc_column_text]\u00a0[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"font-weight: 400;\">La Gesti\u00f3n de Episodios Cr\u00edticos, inserto en el Plan de Descontaminaci\u00f3n Atmosf\u00e9rica del Valle Central de O\u2019Higgins, sin duda que es uno de los temas relevantes para la comunidad y autoridades de las 17 comunas que conforman el \u00e1rea afectada. De all\u00ed que una mayor gama de datos y mediciones siempre es bienvenida para ajustar y perfeccionar a futuro la toma de decisiones en este \u00e1mbito.<\/p>\n<p style=\"font-weight: 400;\">Esta necesidad se plasma en el proyecto del Observatorio de Contaminaci\u00f3n del Aire de O\u2019Higgins, idea que busca avanzar -a nivel regional- en el monitoreo, mediciones y modelamiento num\u00e9rico de la contaminaci\u00f3n, \u201ccon el fin de que la ciudadan\u00eda, por un lado, tenga mayor informaci\u00f3n y, por otro, que las autoridades cuenten con una gama m\u00e1s amplia de datos que puedan luego usar para la toma de decisiones\u201d, explica el acad\u00e9mico del Instituto de Ciencias de la Ingenier\u00eda de la Universidad de O\u2019Higgins y gestor de la iniciativa, Ra\u00fal Valenzuela.<\/p>\n<p style=\"font-weight: 400;\">La iniciativa, respaldada por la UOH y que busca financiamiento a trav\u00e9s de un FIC Regional, ser\u00e1 explicada en el Seminario sobre Calidad del Aire organizado por la serem\u00eda del Medio Ambiente de O\u2019Higgins y la casa de estudios regional, que se realizar\u00e1 el viernes 30 de septiembre, a las 10.00 horas, en el auditorio del Campus Rancagua.<\/p>\n<p style=\"font-weight: 400;\">\u201cDesde la UOH queremos proporcionar conocimiento ingenieril y cient\u00edfico para tener mayores antecedentes de la din\u00e1mica de esos episodios (ambientales), sobre todo porque dependen de la din\u00e1mica atmosf\u00e9rica y tambi\u00e9n de las emisiones existentes a nivel industrial y residencial. Las autoridades normalmente van a poder entender, controlar y medir las cosas que pasan a nivel de emisiones, en la industria y residencial, pero necesitamos el conocimiento cient\u00edfico y t\u00e9cnico para hacer estas mediciones de atm\u00f3sfera, porque tienen una metodolog\u00eda, con instrumentos especializados y adem\u00e1s existen modelos num\u00e9ricos que pueden ser aplicados en la toma de decisiones y en el modelamiento de la contaminaci\u00f3n\u201d, puntualiza el PhD en Ciencias Atmosf\u00e9ricas.<\/p>\n<p style=\"font-weight: 400;\">El investigador a\u00f1adi\u00f3 que parte del proyecto considera no solo la parte t\u00e9cnico-cient\u00edfica, desde el punto de vista atmosf\u00e9rico, \u201ctambi\u00e9n incorporar la visi\u00f3n de salud y econ\u00f3mica del problema, porque es fundamental que podamos establecer cu\u00e1l es el v\u00ednculo que hay, por ejemplo, entre la contaminaci\u00f3n en Rancagua con episodios cr\u00edticos en poblaci\u00f3n m\u00e1s sensible en casos respiratorios, como adultos mayores y ni\u00f1os\u201d.<\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">La seremi de Medio Ambiente de O\u2019Higgins, Giovanna Amaya, explic\u00f3 que \u2013adem\u00e1s de la presentaci\u00f3n del acad\u00e9mico UOH- durante el seminario presencial \u201ccontaremos con otras dos interesantes charlas: el balance en la gesti\u00f3n de episodios cr\u00edticos 2022, es decir, c\u00f3mo estuvo el nivel de contaminaci\u00f3n atmosf\u00e9rica entre los meses de abril y agosto de este a\u00f1o, que estar\u00e1 a mi cargo; y la exposici\u00f3n del senador Juan Luis Castro, quien experto en enfermedades respiratorias, y que se referir\u00e1 al impacto en la salud humana del material particulado 2,5\u201d.\u00a0<\/span><\/p>\n<p style=\"font-weight: 400;\">\u201cEn Chile se estima que viven m\u00e1s de un mill\u00f3n de personas diagnosticadas con una enfermedad rara. Dado el rol p\u00fablico que tiene la Universidad de O&#8217;Higgins, nos alegra mucho la consideraci\u00f3n que hemos tenido en esta instancia\u201d, finaliza el investigador.<\/p>\n<p><b>Investigaci\u00f3n del Acad\u00e9mico:\u00a0<\/b><a href=\"https:\/\/bit.ly\/3fs7xba\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/bit.ly\/3fs7xba&amp;source=gmail&amp;ust=1664465041591000&amp;usg=AOvVaw1nwR3BomzA9KPgKYVN25Wa\"><b>https:\/\/bit.ly\/3fs7xba<\/b><\/a>[\/vc_column_text][vc_column_text]<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650255686594{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center text-right p-md-0 pt-5 pb-5&#8243;][vc_column el_class=&#8221;pb-5&#8243;][vc_row_inner el_class=&#8221;pb-5&#8243;][vc_column_inner]<div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0\"><h2 class=\"title title--decorator title--ms d-inline-block\">Te Recomendamos<\/h2><\/div><\/div><div class=\"content-holder\"><div class=\"row  swipper-news-list not--activate-hack \"><div class=\"row -wrapper\"><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/category\/investigacion\/\">\n                                        Investigaci\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/wp-content\/uploads\/sites\/27\/2026\/04\/FWIS2026-web-op.jpg\" alt=\"Comienza proceso de postulaciones al Premio For Women in Science 2026\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/444;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Jueves 30, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/2026\/04\/30\/comienza-proceso-de-postulaciones-al-premio-for-women-in-science-2026\/\">\n                                    <h3 class=\"small-space\">Comienza proceso de postulaciones al Premio For Women in Science 2026<\/h3><\/a>\n\n                                    <p>La convocatoria, abierta entre el 22 de abril y el 28 de mayo de 2026, busca impulsar la trayectoria y aporte cient\u00edfico de investigadoras chilenas.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/2026\/04\/30\/comienza-proceso-de-postulaciones-al-premio-for-women-in-science-2026\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/category\/investigacion\/\">\n                                        Investigaci\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/wp-content\/uploads\/sites\/27\/2026\/04\/Dia-de-la-Propiedad-Intelectual.jpg\" alt=\"UOH conmemora D\u00eda Mundial de la Propiedad Intelectual destacando avances en protecci\u00f3n\" style=\"--smush-placeholder-width: 2419px; --smush-placeholder-aspect-ratio: 2419\/1609;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Jueves 30, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/2026\/04\/30\/uoh-conmemora-dia-mundial-de-la-propiedad-intelectual-destacando-avances-en-proteccion\/\">\n                                    <h3 class=\"small-space\">UOH conmemora D\u00eda Mundial de la Propiedad Intelectual destacando avances en protecci\u00f3n<\/h3><\/a>\n\n                                    <p>La Direcci\u00f3n de Transferencia e Innovaci\u00f3n ha apoyado la protecci\u00f3n de 21 resultados de investigaci\u00f3n, concretado 11 solicitudes de patente, 12 registros de derechos de autor y 1 marca comercial.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/2026\/04\/30\/uoh-conmemora-dia-mundial-de-la-propiedad-intelectual-destacando-avances-en-proteccion\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/wp-content\/uploads\/sites\/27\/2026\/04\/Inauguracion-Ano-Academico-2026-6.jpg\" alt=\"Reflexi\u00f3n universitaria: UOH inaugura A\u00f1o Acad\u00e9mico 2026 pensando en los desaf\u00edos de la Educaci\u00f3n Superior\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Mi\u00e9rcoles 29, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/2026\/04\/29\/reflexion-universitaria-uoh-inaugura-ano-academico-2026-pensando-en-los-desafios-de-la-educacion-superior\/\">\n                                    <h3 class=\"small-space\">Reflexi\u00f3n universitaria: UOH inaugura A\u00f1o Acad\u00e9mico 2026 pensando en los desaf\u00edos de la Educaci\u00f3n Superior<\/h3><\/a>\n\n                                    <p>La ceremonia promovi\u00f3 el an\u00e1lisis acerca de los cambios educativos que se avecinan dentro de los procesos de formaci\u00f3n universitaria ajustados a contextos digitales.   <\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/2026\/04\/29\/reflexion-universitaria-uoh-inaugura-ano-academico-2026-pensando-en-los-desafios-de-la-educacion-superior\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pagination justify-content-center my-5\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/wp-json\/wp\/v2\/posts\/2105\/\/page\/2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/wp-json\/wp\/v2\/posts\/2105\/\/page\/3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/wp-json\/wp\/v2\/posts\/2105\/\/page\/144\">144<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/wp-json\/wp\/v2\/posts\/2105\/\/page\/2\"><div class=\"icon-pagination-next\"> <?xml version=\"1.0\" ?><svg viewBox=\"0 0 96 96\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><title\/><path d=\"M39.3756,48.0022l30.47-25.39a6.0035,6.0035,0,0,0-7.6878-9.223L26.1563,43.3906a6.0092,6.0092,0,0,0,0,9.2231L62.1578,82.615a6.0035,6.0035,0,0,0,7.6878-9.2231Z\"\/><\/svg> <\/div><\/a><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>  Seg\u00fan explica el acad\u00e9mico del Instituto de Ciencias de la Ingenier\u00eda, Ra\u00fal Valenzuela, el objetivo es avanzar en el monitoreo, mediciones y modelamiento num\u00e9rico de la contaminaci\u00f3n y poner a disposici\u00f3n de la regi\u00f3n mayor informaci\u00f3n y una gama amplia de datos para la toma de decisiones. <\/p>\n","protected":false},"author":34,"featured_media":2108,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-2105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ingenieria-uoh"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Experto UOH expondr\u00e1 proyecto que crea primer Observatorio de Contaminaci\u00f3n del Aire de O\u2019Higgins - Instituto de Ciencias de la Ingenier\u00eda<\/title>\n<meta name=\"description\" content=\"Seg\u00fan explica el acad\u00e9mico del Instituto de Ciencias de la Ingenier\u00eda, Ra\u00fal Valenzuela, el objetivo es avanzar en el monitoreo, mediciones y modelamiento num\u00e9rico de la contaminaci\u00f3n y poner a disposici\u00f3n de la regi\u00f3n mayor informaci\u00f3n y una gama amplia de datos para la toma de decisiones.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Experto UOH expondr\u00e1 proyecto que crea primer Observatorio de Contaminaci\u00f3n del Aire de O\u2019Higgins - Instituto de Ciencias de la Ingenier\u00eda\" \/>\n<meta property=\"og:description\" content=\"Seg\u00fan explica el acad\u00e9mico del Instituto de Ciencias de la Ingenier\u00eda, Ra\u00fal Valenzuela, el objetivo es avanzar en el monitoreo, mediciones y modelamiento num\u00e9rico de la contaminaci\u00f3n y poner a disposici\u00f3n de la regi\u00f3n mayor informaci\u00f3n y una gama amplia de datos para la toma de decisiones.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/2022\/09\/29\/experto-uoh-expondra-proyecto-que-crea-primer-observatorio-de-contaminacion-del-aire-de-ohiggins\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto de Ciencias de la Ingenier\u00eda\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-29T12:28:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-29T12:40:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/wp-content\/uploads\/sites\/27\/2022\/09\/Raul_Valenzuela-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Universidad de O&#039;Higgins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Universidad de O&#039;Higgins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/2022\/09\/29\/experto-uoh-expondra-proyecto-que-crea-primer-observatorio-de-contaminacion-del-aire-de-ohiggins\/\",\"url\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/2022\/09\/29\/experto-uoh-expondra-proyecto-que-crea-primer-observatorio-de-contaminacion-del-aire-de-ohiggins\/\",\"name\":\"Experto UOH expondr\u00e1 proyecto que crea primer Observatorio de Contaminaci\u00f3n del Aire de O\u2019Higgins - Instituto de Ciencias de la Ingenier\u00eda\",\"isPartOf\":{\"@id\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/2022\/09\/29\/experto-uoh-expondra-proyecto-que-crea-primer-observatorio-de-contaminacion-del-aire-de-ohiggins\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/2022\/09\/29\/experto-uoh-expondra-proyecto-que-crea-primer-observatorio-de-contaminacion-del-aire-de-ohiggins\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/wp-content\/uploads\/sites\/27\/2022\/09\/Raul_Valenzuela-.jpg\",\"datePublished\":\"2022-09-29T12:28:16+00:00\",\"dateModified\":\"2022-09-29T12:40:28+00:00\",\"author\":{\"@id\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"description\":\"Seg\u00fan explica el acad\u00e9mico del Instituto de Ciencias de la Ingenier\u00eda, Ra\u00fal Valenzuela, el objetivo es avanzar en el monitoreo, mediciones y modelamiento num\u00e9rico de la contaminaci\u00f3n y poner a disposici\u00f3n de la regi\u00f3n mayor informaci\u00f3n y una gama amplia de datos para la toma de decisiones.\",\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/2022\/09\/29\/experto-uoh-expondra-proyecto-que-crea-primer-observatorio-de-contaminacion-del-aire-de-ohiggins\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/2022\/09\/29\/experto-uoh-expondra-proyecto-que-crea-primer-observatorio-de-contaminacion-del-aire-de-ohiggins\/#primaryimage\",\"url\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/wp-content\/uploads\/sites\/27\/2022\/09\/Raul_Valenzuela-.jpg\",\"contentUrl\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/wp-content\/uploads\/sites\/27\/2022\/09\/Raul_Valenzuela-.jpg\",\"width\":1536,\"height\":1536,\"caption\":\"raul valenzuela\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/#website\",\"url\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/\",\"name\":\"Instituto de Ciencias de la Ingenier\u00eda\",\"description\":\"Otro sitio de Sitios de Universidad O'higgins\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\",\"name\":\"Universidad de O'Higgins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"caption\":\"Universidad de O'Higgins\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Experto UOH expondr\u00e1 proyecto que crea primer Observatorio de Contaminaci\u00f3n del Aire de O\u2019Higgins - Instituto de Ciencias de la Ingenier\u00eda","description":"Seg\u00fan explica el acad\u00e9mico del Instituto de Ciencias de la Ingenier\u00eda, Ra\u00fal Valenzuela, el objetivo es avanzar en el monitoreo, mediciones y modelamiento num\u00e9rico de la contaminaci\u00f3n y poner a disposici\u00f3n de la regi\u00f3n mayor informaci\u00f3n y una gama amplia de datos para la toma de decisiones.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Experto UOH expondr\u00e1 proyecto que crea primer Observatorio de Contaminaci\u00f3n del Aire de O\u2019Higgins - Instituto de Ciencias de la Ingenier\u00eda","og_description":"Seg\u00fan explica el acad\u00e9mico del Instituto de Ciencias de la Ingenier\u00eda, Ra\u00fal Valenzuela, el objetivo es avanzar en el monitoreo, mediciones y modelamiento num\u00e9rico de la contaminaci\u00f3n y poner a disposici\u00f3n de la regi\u00f3n mayor informaci\u00f3n y una gama amplia de datos para la toma de decisiones.","og_url":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/2022\/09\/29\/experto-uoh-expondra-proyecto-que-crea-primer-observatorio-de-contaminacion-del-aire-de-ohiggins\/","og_site_name":"Instituto de Ciencias de la Ingenier\u00eda","article_published_time":"2022-09-29T12:28:16+00:00","article_modified_time":"2022-09-29T12:40:28+00:00","og_image":[{"width":1536,"height":1536,"url":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/wp-content\/uploads\/sites\/27\/2022\/09\/Raul_Valenzuela-.jpg","type":"image\/jpeg"}],"author":"Universidad de O'Higgins","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Universidad de O'Higgins","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/2022\/09\/29\/experto-uoh-expondra-proyecto-que-crea-primer-observatorio-de-contaminacion-del-aire-de-ohiggins\/","url":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/2022\/09\/29\/experto-uoh-expondra-proyecto-que-crea-primer-observatorio-de-contaminacion-del-aire-de-ohiggins\/","name":"Experto UOH expondr\u00e1 proyecto que crea primer Observatorio de Contaminaci\u00f3n del Aire de O\u2019Higgins - Instituto de Ciencias de la Ingenier\u00eda","isPartOf":{"@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/2022\/09\/29\/experto-uoh-expondra-proyecto-que-crea-primer-observatorio-de-contaminacion-del-aire-de-ohiggins\/#primaryimage"},"image":{"@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/2022\/09\/29\/experto-uoh-expondra-proyecto-que-crea-primer-observatorio-de-contaminacion-del-aire-de-ohiggins\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/wp-content\/uploads\/sites\/27\/2022\/09\/Raul_Valenzuela-.jpg","datePublished":"2022-09-29T12:28:16+00:00","dateModified":"2022-09-29T12:40:28+00:00","author":{"@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"description":"Seg\u00fan explica el acad\u00e9mico del Instituto de Ciencias de la Ingenier\u00eda, Ra\u00fal Valenzuela, el objetivo es avanzar en el monitoreo, mediciones y modelamiento num\u00e9rico de la contaminaci\u00f3n y poner a disposici\u00f3n de la regi\u00f3n mayor informaci\u00f3n y una gama amplia de datos para la toma de decisiones.","inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/2022\/09\/29\/experto-uoh-expondra-proyecto-que-crea-primer-observatorio-de-contaminacion-del-aire-de-ohiggins\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/2022\/09\/29\/experto-uoh-expondra-proyecto-que-crea-primer-observatorio-de-contaminacion-del-aire-de-ohiggins\/#primaryimage","url":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/wp-content\/uploads\/sites\/27\/2022\/09\/Raul_Valenzuela-.jpg","contentUrl":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/wp-content\/uploads\/sites\/27\/2022\/09\/Raul_Valenzuela-.jpg","width":1536,"height":1536,"caption":"raul valenzuela"},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/#website","url":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/","name":"Instituto de Ciencias de la Ingenier\u00eda","description":"Otro sitio de Sitios de Universidad O'higgins","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f","name":"Universidad de O'Higgins","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","caption":"Universidad de O'Higgins"}}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/wp-json\/wp\/v2\/posts\/2105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/wp-json\/wp\/v2\/comments?post=2105"}],"version-history":[{"count":1,"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/wp-json\/wp\/v2\/posts\/2105\/revisions"}],"predecessor-version":[{"id":2107,"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/wp-json\/wp\/v2\/posts\/2105\/revisions\/2107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/wp-json\/wp\/v2\/media\/2108"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/wp-json\/wp\/v2\/media?parent=2105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/wp-json\/wp\/v2\/categories?post=2105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-ingenieria\/wp-json\/wp\/v2\/tags?post=2105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}