
{"id":2077,"date":"2022-12-19T17:53:40","date_gmt":"2022-12-19T20:53:40","guid":{"rendered":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/2022\/12\/19\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\/"},"modified":"2022-12-19T17:53:40","modified_gmt":"2022-12-19T20:53:40","slug":"docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica","status":"publish","type":"post","link":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/2022\/12\/19\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\/","title":{"rendered":"Docentes en ejercicio y en formaci\u00f3n conocieron sobre ansiedad, estereotipos de g\u00e9nero y aprendizaje de la matem\u00e1tica"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center text-right circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row][vc_column]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\"><span itemprop=\"name\">Instituto de Ciencias de la Educaci\u00f3n<\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/noticias\/\"><span itemprop=\"name\">Noticias<\/span><\/a><meta itemprop=\"position\" content=\"3\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Docentes en ejercicio y en formaci\u00f3n conocieron sobre ansiedad, estereotipos <\/span><meta itemprop=\"position\" content=\"4\" \/><\/ol><\/div><ul class=\"p-0 list-style-none d-inline-block\"><li class=\"p-0\"><a href=https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/category\/educacion\/ class=\"px-1 py-2\">Educaci\u00f3n<\/a><\/li><\/ul><div class=\"date_publish_post\"> \u25cf Lun 19 de Diciembre 2022<\/div><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block title--decorator  big\">Docentes en ejercicio y en formaci\u00f3n conocieron sobre ansiedad, estereotipos de g\u00e9nero y aprendizaje de la matem\u00e1tica<\/h1><\/div>[vc_row_inner el_class=&#8221;border-separator m-0&#8243;][vc_column_inner width=&#8221;2\/3&#8243;]<div class=\"author_wp_class\"> Escrito por <span>Universidad de O'Higgins<\/span><\/div>[\/vc_column_inner][vc_column_inner el_class=&#8221;align-items-end-publish&#8221; width=&#8221;1\/3&#8243;]<div class=\"uoh_social_network_component uoh_row col-12 justify-content-end m-0 p-0\"> <div class=\"icon__facebook-share-button\">\n                       <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/2022\/12\/19\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\/\" target=\"_blank\"> <div class=\"icon__facebook-svg\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22.4px\" height=\"48.3px\" viewBox=\"0 0 22.4 48.3\" style=\"overflow:visible;enable-background:new 0 0 22.4 48.3;\" xml:space=\"preserve\">\n                <defs>\n                <\/defs>\n                <path class=\"st0\" d=\"M22.4,15.6h-7.6v-5c0-1.9,1.2-2.3,2.1-2.3c0.9,0,5.4,0,5.4,0V0l-7.4,0C6.6,0,4.8,6.2,4.8,10.1v5.5H0v8.5h4.8\n                    c0,10.9,0,24.1,0,24.1h10c0,0,0-13.3,0-24.1h6.8L22.4,15.6z\"><\/path>\n                <\/svg><\/a><\/div>\n                    <\/div><div class=\"icon__twitter-share-button\">\n                        <div class=\"icon__twitter-svg\"><a target=\"_blank\" href=\"http:\/\/twitter.com\/share?url=https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/2022\/12\/19\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/a><\/div>\n                        <\/div><div class=\"icon__linkedin-share-button\">\n                        <div class=\"icon__linkedin-svg\">\n                        <a target=\"__blank\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/2022\/12\/19\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\/\"><svg enable-background=\"new 0 0 100 100\" height=\"100px\" id=\"Layer_1\" version=\"1.1\" viewBox=\"0 0 100 100\" width=\"100px\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><circle cx=\"50\" cy=\"50\" fill=\"#ccc\" r=\"45\"\/><g id=\"LinkedIn_1_\"><rect fill=\"#FFFFFF\" height=\"24.361\" width=\"7.69\" x=\"31.271\" y=\"43.569\"\/><path d=\"M59.968,43.334c-4.406,0-7.165,2.387-7.677,4.058v-3.823h-8.636c0.109,2.03,0,24.361,0,24.361h8.636    V54.748c0-0.733-0.034-1.465,0.19-1.991c0.594-1.464,1.869-2.985,4.162-2.985c2.998,0,4.361,2.253,4.361,5.552V67.93h8.721V54.384    C69.726,46.839,65.432,43.334,59.968,43.334z\" fill=\"#FFFFFF\"\/><path d=\"M34.973,32.069c-2.839,0-4.696,1.823-4.696,4.229c0,2.361,1.804,4.224,4.589,4.224h0.054    c2.891,0,4.69-1.869,4.69-4.229C39.555,33.888,37.81,32.069,34.973,32.069z\" fill=\"#FFFFFF\"\/><\/g><\/g><\/svg><\/a><\/div>\n\n            <\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_single_image image=&#8221;15956&#8243; img_size=&#8221;full&#8221;][vc_column_text]\u00a0[\/vc_column_text][vc_column_text]<em>Las y los asistentes pudieron reflexionar sobre los factores \u2013asociados a la ense\u00f1anza- que favorecen y obstaculizan el aprendizaje de las matem\u00e1ticas en el contexto escolar.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>[\/vc_column_text][vc_column_text]\u00a0[\/vc_column_text][vc_column_text]En el marco de las actividades del N\u00facleo Milenio para el Estudio del Desarrollo de las Habilidades Matem\u00e1ticas Tempranas (MEMAT), el Instituto de Ciencias de la Educaci\u00f3n (ICEd) de la Universidad de O\u2019Higgins realiz\u00f3 el Taller: &#8220;Ansiedad, estereotipos de g\u00e9nero y aprendizaje de la matem\u00e1tica&#8221;, dirigido a docentes en ejercicio y en formaci\u00f3n.<\/p>\n<p>La actividad, que estuvo a cargo del acad\u00e9mico del ICEd, David G\u00f3mez, y de la investigadora postdoctoral del ICEd, Ana Mar\u00eda Espinoza, profundiz\u00f3 en las caracter\u00edsticas y manifestaciones de la ansiedad matem\u00e1tica, las creencias en torno a esta disciplina, as\u00ed como en la relaci\u00f3n entre g\u00e9nero y matem\u00e1tica. Adem\u00e1s, se promovi\u00f3 la reflexi\u00f3n sobre las diversas manifestaciones de estas tem\u00e1ticas en el aula, as\u00ed como formas para enfrentarlas desde la pedagog\u00eda.<\/p>\n<p>El Dr. G\u00f3mez aclar\u00f3 que la ansiedad matem\u00e1tica se refleja en sentimientos de tensi\u00f3n y ansiedad que interfieren en el trabajo con n\u00fameros y la resoluci\u00f3n de problemas matem\u00e1ticos en una gran variedad de situaciones cotidianas y acad\u00e9micas. Esto puede producir que las y los estudiantes se sientan expuestos y con la idea de enfrentarse a un problema cuya soluci\u00f3n queda fuera de su alcance, adem\u00e1s de no encontrarle sentido a los procedimientos matem\u00e1ticos.<\/p>\n<p>\u201cDe no contrarrestarse este tipo de episodios, puede generar conductas de evitaci\u00f3n y empezar a ser incorporadas en la identidad de la persona\u201d, explic\u00f3 el Dr. David G\u00f3mez, quien puntualiza que es necesario reconocer y abordar en el aula estos episodios de ansiedad matem\u00e1tica, buscando validar las emociones del estudiantado, como pudiera ser el bloqueo o el \u201cquedarse en blanco\u201d, y evitar las situaciones de exposici\u00f3n personal en el aula, optando \u2013por ejemplo- por dar preferencia al trabajo grupal frente al individual.<\/p>\n<p>El acad\u00e9mico tambi\u00e9n se refiri\u00f3 a los \u2018mitos\u2019 sobre las matem\u00e1ticas, como que solo algunas personas tengan una mente matem\u00e1tica, o que todo problema matem\u00e1tico solo tiene una respuesta correcta. Estos mitos generan una visi\u00f3n limitada de lo que es hacer matem\u00e1ticas, poniendo \u2013adem\u00e1s- un \u00e9nfasis conductista.<\/p>\n<p>En la jornada tambi\u00e9n se plante\u00f3, a trav\u00e9s de la exposici\u00f3n de la Dra. Ana Mar\u00eda Espinoza, la relaci\u00f3n entre matem\u00e1ticas y g\u00e9nero, mostrando situaciones \u2013propuestas por las\/os mismas\/os asistentes- y barreras que muchas mujeres deben enfrentar para estudiar matem\u00e1ticas, o los ambientes machistas existentes en algunos entornos educativos.<\/p>\n<p>\u201cPromover espacios de reflexi\u00f3n sobre estas tem\u00e1ticas es fundamental para avanzar en la transformaci\u00f3n de situaciones que afectan el aprendizaje y desarrollo equitativo de habilidades matem\u00e1ticas. Las y los docentes son claves para la eliminaci\u00f3n de las barreras que generan estos fen\u00f3menos psicosociales\u201d, finaliz\u00f3 la investigadora postdoctoral Ana Mar\u00eda Espinoza.<\/p>\n<p>&nbsp;<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650255686594{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center text-right p-md-0 pt-5 pb-5&#8243;][vc_column el_class=&#8221;pb-5&#8243;][vc_row_inner el_class=&#8221;pb-5&#8243;][vc_column_inner]<div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0\"><h2 class=\"title title--decorator title--ms d-inline-block\">Te Recomendamos<\/h2><\/div><\/div><div class=\"content-holder\"><div class=\"row  swipper-news-list not--activate-hack \"><div class=\"row -wrapper\"><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/category\/acreditacion\/\">\n                                        Acreditaci\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-content\/uploads\/sites\/13\/2026\/06\/Acreditacion-Mesas-de-trabajo-con-estudiantes-14.jpg\" alt=\"Mesa de Di\u00e1logo Estudiantil reuni\u00f3 voces de la comunidad universitaria en el marco de la Acreditaci\u00f3n 2027\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/882;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Lunes 15, Junio<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/2026\/06\/15\/mesa-de-dialogo-estudiantil-reunio-voces-de-la-comunidad-universitaria-en-el-marco-de-la-acreditacion-2027\/\">\n                                    <h3 class=\"small-space\">Mesa de Di\u00e1logo Estudiantil reuni\u00f3 voces de la comunidad universitaria en el marco de la Acreditaci\u00f3n 2027<\/h3><\/a>\n\n                                    <p>Estudiantes de distintas carreras reflexionaron sobre aquellos aspectos que distinguen a la instituci\u00f3n y tambi\u00e9n sobre las oportunidades de mejora que permitan fortalecer la experiencia universitaria.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/2026\/06\/15\/mesa-de-dialogo-estudiantil-reunio-voces-de-la-comunidad-universitaria-en-el-marco-de-la-acreditacion-2027\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/category\/educacion\/\">\n                                        Educaci\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-content\/uploads\/sites\/13\/2026\/06\/Gabriela-Gomez.png\" alt=\"Acad\u00e9mica y directora del ICEd integrar\u00e1 el Consejo Nacional del Libro y la Lectura\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Viernes 5, Junio<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/2026\/06\/05\/academica-y-directora-del-iced-integrara-el-consejo-nacional-del-libro-y-la-lectura\/\">\n                                    <h3 class=\"small-space\">Acad\u00e9mica y directora del ICEd integrar\u00e1 el Consejo Nacional del Libro y la Lectura<\/h3><\/a>\n\n                                    <p>Gabriela G\u00f3mez ser\u00e1 representante del Consejo de Rectoras y Rectores de la Universidades Chilenas en dicha entidad.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/2026\/06\/05\/academica-y-directora-del-iced-integrara-el-consejo-nacional-del-libro-y-la-lectura\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-content\/uploads\/sites\/13\/2026\/06\/Presentacion-PDE-2026-20.jpg\" alt=\"UOH lanza su Plan de Desarrollo Estrat\u00e9gico 2026-2030 con miras a consolidar su cultura de calidad institucional\" style=\"--smush-placeholder-width: 1470px; --smush-placeholder-aspect-ratio: 1470\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Lunes 1, Junio<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/2026\/06\/01\/uoh-lanza-su-plan-de-desarrollo-estrategico-2026-2030-con-miras-a-consolidar-su-cultura-de-calidad-institucional\/\">\n                                    <h3 class=\"small-space\">UOH lanza su Plan de Desarrollo Estrat\u00e9gico 2026-2030 con miras a consolidar su cultura de calidad institucional<\/h3><\/a>\n\n                                    <p>La iniciativa, liderada por la Direcci\u00f3n de Desarrollo Institucional, contempla mecanismos de seguimiento y mejora continua orientados a fortalecer el v\u00ednculo de la Universidad con el territorio y los desaf\u00edos globales.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/2026\/06\/01\/uoh-lanza-su-plan-de-desarrollo-estrategico-2026-2030-con-miras-a-consolidar-su-cultura-de-calidad-institucional\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pagination justify-content-center my-5\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-json\/wp\/v2\/posts\/2077\/\/page\/2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-json\/wp\/v2\/posts\/2077\/\/page\/3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-json\/wp\/v2\/posts\/2077\/\/page\/114\">114<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-json\/wp\/v2\/posts\/2077\/\/page\/2\"><div class=\"icon-pagination-next\"> <?xml version=\"1.0\" ?><svg viewBox=\"0 0 96 96\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><title\/><path d=\"M39.3756,48.0022l30.47-25.39a6.0035,6.0035,0,0,0-7.6878-9.223L26.1563,43.3906a6.0092,6.0092,0,0,0,0,9.2231L62.1578,82.615a6.0035,6.0035,0,0,0,7.6878-9.2231Z\"\/><\/svg> <\/div><\/a><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Las y los asistentes pudieron reflexionar sobre los factores \u2013asociados a la ense\u00f1anza- que favorecen y obstaculizan el aprendizaje de las matem\u00e1ticas en el contexto escolar.<\/p>\n","protected":false},"author":34,"featured_media":2078,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[46],"tags":[],"class_list":["post-2077","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Docentes en ejercicio y en formaci\u00f3n conocieron sobre ansiedad, estereotipos de g\u00e9nero y aprendizaje de la matem\u00e1tica - Instituto de Ciencias de la Educaci\u00f3n<\/title>\n<meta name=\"description\" content=\"Las y los asistentes pudieron reflexionar sobre los factores \u2013asociados a la ense\u00f1anza- que favorecen y obstaculizan el aprendizaje de las matem\u00e1ticas en el contexto escolar.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Docentes en ejercicio y en formaci\u00f3n conocieron sobre ansiedad, estereotipos de g\u00e9nero y aprendizaje de la matem\u00e1tica - Instituto de Ciencias de la Educaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Las y los asistentes pudieron reflexionar sobre los factores \u2013asociados a la ense\u00f1anza- que favorecen y obstaculizan el aprendizaje de las matem\u00e1ticas en el contexto escolar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/2022\/12\/19\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto de Ciencias de la Educaci\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-19T20:53:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-content\/uploads\/sites\/13\/2022\/12\/METAT.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Universidad de O&#039;Higgins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Universidad de O&#039;Higgins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-de-ciencias-de-la-educacion\\\/2022\\\/12\\\/19\\\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-de-ciencias-de-la-educacion\\\/2022\\\/12\\\/19\\\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\\\/\"},\"author\":{\"name\":\"Universidad de O'Higgins\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-de-ciencias-de-la-educacion\\\/#\\\/schema\\\/person\\\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"headline\":\"Docentes en ejercicio y en formaci\u00f3n conocieron sobre ansiedad, estereotipos de g\u00e9nero y aprendizaje de la matem\u00e1tica\",\"datePublished\":\"2022-12-19T20:53:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-de-ciencias-de-la-educacion\\\/2022\\\/12\\\/19\\\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\\\/\"},\"wordCount\":759,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-de-ciencias-de-la-educacion\\\/2022\\\/12\\\/19\\\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-de-ciencias-de-la-educacion\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2022\\\/12\\\/METAT.jpg\",\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.uoh.cl\\\/instituto-de-ciencias-de-la-educacion\\\/2022\\\/12\\\/19\\\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-de-ciencias-de-la-educacion\\\/2022\\\/12\\\/19\\\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\\\/\",\"url\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-de-ciencias-de-la-educacion\\\/2022\\\/12\\\/19\\\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\\\/\",\"name\":\"Docentes en ejercicio y en formaci\u00f3n conocieron sobre ansiedad, estereotipos de g\u00e9nero y aprendizaje de la matem\u00e1tica - Instituto de Ciencias de la Educaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-de-ciencias-de-la-educacion\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-de-ciencias-de-la-educacion\\\/2022\\\/12\\\/19\\\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-de-ciencias-de-la-educacion\\\/2022\\\/12\\\/19\\\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-de-ciencias-de-la-educacion\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2022\\\/12\\\/METAT.jpg\",\"datePublished\":\"2022-12-19T20:53:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-de-ciencias-de-la-educacion\\\/#\\\/schema\\\/person\\\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"description\":\"Las y los asistentes pudieron reflexionar sobre los factores \u2013asociados a la ense\u00f1anza- que favorecen y obstaculizan el aprendizaje de las matem\u00e1ticas en el contexto escolar.\",\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uoh.cl\\\/instituto-de-ciencias-de-la-educacion\\\/2022\\\/12\\\/19\\\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-de-ciencias-de-la-educacion\\\/2022\\\/12\\\/19\\\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-de-ciencias-de-la-educacion\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2022\\\/12\\\/METAT.jpg\",\"contentUrl\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-de-ciencias-de-la-educacion\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2022\\\/12\\\/METAT.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-de-ciencias-de-la-educacion\\\/#website\",\"url\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-de-ciencias-de-la-educacion\\\/\",\"name\":\"Instituto de Ciencias de la Educaci\u00f3n\",\"description\":\"Otro sitio de Sitios de Universidad O&#039;higgins\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-de-ciencias-de-la-educacion\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-de-ciencias-de-la-educacion\\\/#\\\/schema\\\/person\\\/ea242e676c7d6d7e46fc8b9e39486c4f\",\"name\":\"Universidad de O'Higgins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"caption\":\"Universidad de O'Higgins\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Docentes en ejercicio y en formaci\u00f3n conocieron sobre ansiedad, estereotipos de g\u00e9nero y aprendizaje de la matem\u00e1tica - Instituto de Ciencias de la Educaci\u00f3n","description":"Las y los asistentes pudieron reflexionar sobre los factores \u2013asociados a la ense\u00f1anza- que favorecen y obstaculizan el aprendizaje de las matem\u00e1ticas en el contexto escolar.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Docentes en ejercicio y en formaci\u00f3n conocieron sobre ansiedad, estereotipos de g\u00e9nero y aprendizaje de la matem\u00e1tica - Instituto de Ciencias de la Educaci\u00f3n","og_description":"Las y los asistentes pudieron reflexionar sobre los factores \u2013asociados a la ense\u00f1anza- que favorecen y obstaculizan el aprendizaje de las matem\u00e1ticas en el contexto escolar.","og_url":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/2022\/12\/19\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\/","og_site_name":"Instituto de Ciencias de la Educaci\u00f3n","article_published_time":"2022-12-19T20:53:40+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-content\/uploads\/sites\/13\/2022\/12\/METAT.jpg","type":"image\/jpeg"}],"author":"Universidad de O'Higgins","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Universidad de O'Higgins","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/2022\/12\/19\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\/#article","isPartOf":{"@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/2022\/12\/19\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\/"},"author":{"name":"Universidad de O'Higgins","@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"headline":"Docentes en ejercicio y en formaci\u00f3n conocieron sobre ansiedad, estereotipos de g\u00e9nero y aprendizaje de la matem\u00e1tica","datePublished":"2022-12-19T20:53:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/2022\/12\/19\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\/"},"wordCount":759,"commentCount":0,"image":{"@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/2022\/12\/19\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-content\/uploads\/sites\/13\/2022\/12\/METAT.jpg","articleSection":["Educaci\u00f3n"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/2022\/12\/19\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/2022\/12\/19\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\/","url":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/2022\/12\/19\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\/","name":"Docentes en ejercicio y en formaci\u00f3n conocieron sobre ansiedad, estereotipos de g\u00e9nero y aprendizaje de la matem\u00e1tica - Instituto de Ciencias de la Educaci\u00f3n","isPartOf":{"@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/2022\/12\/19\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\/#primaryimage"},"image":{"@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/2022\/12\/19\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-content\/uploads\/sites\/13\/2022\/12\/METAT.jpg","datePublished":"2022-12-19T20:53:40+00:00","author":{"@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"description":"Las y los asistentes pudieron reflexionar sobre los factores \u2013asociados a la ense\u00f1anza- que favorecen y obstaculizan el aprendizaje de las matem\u00e1ticas en el contexto escolar.","inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/2022\/12\/19\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/2022\/12\/19\/docentes-en-ejercicio-y-en-formacion-conocieron-sobre-ansiedad-estereotipos-de-genero-y-aprendizaje-de-la-matematica\/#primaryimage","url":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-content\/uploads\/sites\/13\/2022\/12\/METAT.jpg","contentUrl":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-content\/uploads\/sites\/13\/2022\/12\/METAT.jpg","width":1000,"height":1000},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/#website","url":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/","name":"Instituto de Ciencias de la Educaci\u00f3n","description":"Otro sitio de Sitios de Universidad O&#039;higgins","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f","name":"Universidad de O'Higgins","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","caption":"Universidad de O'Higgins"}}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-json\/wp\/v2\/posts\/2077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-json\/wp\/v2\/comments?post=2077"}],"version-history":[{"count":0,"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-json\/wp\/v2\/posts\/2077\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-json\/wp\/v2\/media\/2078"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-json\/wp\/v2\/media?parent=2077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-json\/wp\/v2\/categories?post=2077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-json\/wp\/v2\/tags?post=2077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}