
{"id":201,"date":"2022-04-29T13:48:19","date_gmt":"2022-04-29T16:48:19","guid":{"rendered":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/academico\/jose-mela\/"},"modified":"2026-05-13T07:01:59","modified_gmt":"2026-05-13T10:01:59","slug":"jose-mela","status":"publish","type":"academics","link":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/academico\/jose-mela\/","title":{"rendered":"Jos\u00e9 Mela"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1650056176159{padding-top: 3rem !important;}&#8221;][vc_row][vc_column][vc_wp_custommenu nav_menu=&#8221;5&#8243;]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\"><span itemprop=\"name\">Instituto de Ciencias de la Educaci\u00f3n<\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/investigacion\"><span itemprop=\"name\">Investigaci\u00f3n<\/span><\/a><meta itemprop=\"position\" content=\"3\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/investigacion\/academicos\"><span itemprop=\"name\">Acad\u00e9micos<\/span><\/a><meta itemprop=\"position\" content=\"4\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Jos\u00e9 Mela <\/span><meta itemprop=\"position\" content=\"5\" \/><\/ol><\/div><ul class=\"p-0 list-style-none d-inline-block\"><\/ul><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block big\">Jos\u00e9 Mela<em class=\"position__title\"> <span>\u25cf<\/span> Profesor Asociado<\/em><\/h1><\/div>[vc_row_inner el_class=&#8221;border-separator m-0 mt-4&#8243;][vc_column_inner width=&#8221;1\/6&#8243;]<div class=\"vc_single_image-wrapper vc_box_rounded  vc_box_border_grey\"><img decoding=\"async\" width=\"1024\" height=\"1024\" data-src=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-content\/uploads\/sites\/13\/2025\/09\/Jose-Mela-1-1024x1024.jpg\" class=\"attachment-large size-large wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-content\/uploads\/sites\/13\/2025\/09\/Jose-Mela-1-1024x1024.jpg 1024w, https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-content\/uploads\/sites\/13\/2025\/09\/Jose-Mela-1-300x300.jpg 300w, https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-content\/uploads\/sites\/13\/2025\/09\/Jose-Mela-1-150x150.jpg 150w, https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-content\/uploads\/sites\/13\/2025\/09\/Jose-Mela-1-768x768.jpg 768w, https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-content\/uploads\/sites\/13\/2025\/09\/Jose-Mela-1-600x600.jpg 600w, https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-content\/uploads\/sites\/13\/2025\/09\/Jose-Mela-1.jpg 1080w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/1024;\" \/><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;2\/3&#8243;]<div class=\"block--info\">\n                                <div class=\"sub_title__grade\">Grado Acad\u00e9mico<\/div>\n                                <h3>Doctor en Artes y Educaci\u00f3n, U. Barcelona., Mag\u00edster en Educaci\u00f3n Interdisciplinar de las Artes, U. de Barcelona.<\/h3> <\/div><div class=\"block--info\">\n                                <div class=\"sub_title__grade\">T\u00edtulo(s) Profesional<\/div>\n                                <h3>Profesor de Artes Pl\u00e1sticas.<\/h3> <\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;]<div class=\"uoh_social_network_component uoh_row col-12 justify-content-end m-0 p-0\"> <div class=\"icon__facebook-share-button\">\n                       <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/academico\/jose-mela\/\" target=\"_blank\"> <div class=\"icon__facebook-svg\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22.4px\" height=\"48.3px\" viewBox=\"0 0 22.4 48.3\" style=\"overflow:visible;enable-background:new 0 0 22.4 48.3;\" xml:space=\"preserve\">\n                <defs>\n                <\/defs>\n                <path class=\"st0\" d=\"M22.4,15.6h-7.6v-5c0-1.9,1.2-2.3,2.1-2.3c0.9,0,5.4,0,5.4,0V0l-7.4,0C6.6,0,4.8,6.2,4.8,10.1v5.5H0v8.5h4.8\n                    c0,10.9,0,24.1,0,24.1h10c0,0,0-13.3,0-24.1h6.8L22.4,15.6z\"><\/path>\n                <\/svg><\/a><\/div>\n                    <\/div><div class=\"icon__twitter-share-button\">\n                        <div class=\"icon__twitter-svg\"><a target=\"_blank\" href=\"http:\/\/twitter.com\/share?url=https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/academico\/jose-mela\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/a><\/div>\n                        <\/div><div class=\"icon__linkedin-share-button\">\n                        <div class=\"icon__linkedin-svg\">\n                        <a target=\"__blank\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/academico\/jose-mela\/\"><svg enable-background=\"new 0 0 100 100\" height=\"100px\" id=\"Layer_1\" version=\"1.1\" viewBox=\"0 0 100 100\" width=\"100px\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><circle cx=\"50\" cy=\"50\" fill=\"#ccc\" r=\"45\"\/><g id=\"LinkedIn_1_\"><rect fill=\"#FFFFFF\" height=\"24.361\" width=\"7.69\" x=\"31.271\" y=\"43.569\"\/><path d=\"M59.968,43.334c-4.406,0-7.165,2.387-7.677,4.058v-3.823h-8.636c0.109,2.03,0,24.361,0,24.361h8.636    V54.748c0-0.733-0.034-1.465,0.19-1.991c0.594-1.464,1.869-2.985,4.162-2.985c2.998,0,4.361,2.253,4.361,5.552V67.93h8.721V54.384    C69.726,46.839,65.432,43.334,59.968,43.334z\" fill=\"#FFFFFF\"\/><path d=\"M34.973,32.069c-2.839,0-4.696,1.823-4.696,4.229c0,2.361,1.804,4.224,4.589,4.224h0.054    c2.891,0,4.69-1.869,4.69-4.229C39.555,33.888,37.81,32.069,34.973,32.069z\" fill=\"#FFFFFF\"\/><\/g><\/g><\/svg><\/a><\/div>\n\n            <\/div><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650239278498{background-color: #ffffff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center&#8221;][vc_column][vc_row_inner][vc_column_inner width=&#8221;5\/6&#8243;]<div class=\"uoh_title_component-container\"><h4 class=\"title title--ms d-inline-block title--decorator  small\">Descripci\u00f3n<\/h4><\/div><p class=\"info-headings mb-2 text-left mt-4 mt-md-2\">Finaliz\u00f3 sus estudios de M\u00e1ster en Educaci\u00f3n Interdisciplinar de las Artes en la Universidad de Barcelona en el a\u00f1o 2012, para continuar estudios de doctorado en Artes y Educaci\u00f3n en la misma instituci\u00f3n. Se ha dedicado a investigar sobre la identidad mapuche urbana en adolescentes, a trav\u00e9s del uso de metodolog\u00edas visuales, como la fotograf\u00eda, para reunir evidencias y evocar nuevos significados. Actualmente, se dedica a la creaci\u00f3n art\u00edstica, la docencia universitaria y a escribir sobre la Investigaci\u00f3n Basada en las Artes, Interculturalidad y los diversos procesos de construcci\u00f3n identitaria de pueblos originarios como el mapuche.<\/p>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650056119592{background-color: #ffffff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5 pb-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-start&#8221;][vc_column width=&#8221;1\/6&#8243; el_class=&#8221;p-0&#8243;]<div class=\"uoh_link_component pe-4 d-inline-block py-1 button_icon inline\"><i class=\"me-2 fas fa-newspaper\" style=\"color: #42a0f8\"><\/i><span>Publicaciones<\/span><\/div><div class=\"wpb_text_column wpb_content_element  citas mb-3 pb-3\"><div class=\"wpb_wrapper\"><p>10<\/p><\/div><\/div><div class=\"uoh_link_component pe-4 d-inline-block py-1 button_icon inline\"><i class=\"me-2 fas fa-project-diagram\" style=\"color: #42a0f8\"><\/i><span>Proyectos<\/span><\/div><div class=\"wpb_text_column wpb_content_element  citas mb-3 pb-3\"><div class=\"wpb_wrapper\"><p>16<\/p><\/div><\/div><div class=\"uoh_link_component pe-4 d-inline-block py-1 button_icon inline\"><i class=\"me-2 fas fa-book\" style=\"color: #42a0f8\"><\/i><span>Libros y Monograf\u00edas<\/span><\/div><div class=\"wpb_text_column wpb_content_element  citas mb-3 pb-3\"><div class=\"wpb_wrapper\"><p>1<\/p><\/div><\/div><div class=\"uoh_link_component pe-4 d-inline-block py-1 button_icon inline\"><i class=\"me-2 fas fa-book-bookmark\" style=\"color: #42a0f8\"><\/i><span>Cap\u00edtulos de Libros<\/span><\/div><div class=\"wpb_text_column wpb_content_element  citas mb-3 pb-3\"><div class=\"wpb_wrapper\"><p>8<\/p><\/div><\/div>[\/vc_column][vc_column width=&#8221;5\/6&#8243;][vc_tta_tabs active_section=&#8221;1&#8243; el_class=&#8221;tabs-inner-academic&#8221;][vc_tta_section title=&#8221;Publicaciones&#8221; tab_id=&#8221;publicaciones&#8221;]<link rel=\"stylesheet\" id=\"font-awesome-css\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.5.1\/css\/all.min.css\" type=\"text\/css\" media=\"all\"><div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0 px-md-0 \"><\/div><\/div>[\/vc_tta_section][vc_tta_section title=&#8221;Proyectos&#8221; tab_id=&#8221;proyectos&#8221;]<link rel=\"stylesheet\" id=\"font-awesome-css\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.5.1\/css\/all.min.css\" type=\"text\/css\" media=\"all\"><div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0 px-md-0 \"><\/div><\/div>[\/vc_tta_section][vc_tta_section title=&#8221;Libros y Monografias&#8221; tab_id=&#8221;libros&#8221;]<link rel=\"stylesheet\" id=\"font-awesome-css\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.5.1\/css\/all.min.css\" type=\"text\/css\" media=\"all\"><div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0 px-md-0 \"><\/div><\/div><div class=\"content-holder row m-0 p-0 aling-items-center pt-5 pb-5 \"><div class=\"row  large--swipper-content p-0 \"><div class=\"\"><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-location-dot fa-fw\"><\/i> Chile - <\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Ense\u00f1anza de las artes en contexto de ruralidad Principales resultados del estudio en Educaci\u00f3n art\u00edstica en escuelas p\u00fablicas de la Regi\u00f3n de O\u0092Higgins<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-956-6147-14-5<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>N\u00b0 de P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">113-130<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad de Magallanes<\/small>\n        <\/div>        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Trabucco, Sergio<\/small>\n        <\/div>        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Jos\u00e9 Israel Mela Contreras<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-location-dot fa-fw\"><\/i> Chile - <\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Ense\u00f1anza de las artes en contexto de ruralidad Principales resultados del estudio en Educaci\u00f3n art\u00edstica en escuelas p\u00fablicas de la Regi\u00f3n de O\u0092Higgins<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-956-6147-14-5<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>N\u00b0 de P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">113-130<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad de Magallanes<\/small>\n        <\/div>        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Trabucco, Sergio<\/small>\n        <\/div>        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Jos\u00e9 Israel Mela Contreras<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>[\/vc_tta_section][vc_tta_section title=&#8221;Cap\u00edtulos de Libros&#8221; tab_id=&#8221;cap-libros&#8221;]<link rel=\"stylesheet\" id=\"font-awesome-css\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.5.1\/css\/all.min.css\" type=\"text\/css\" media=\"all\"><div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0 px-md-0 \"><\/div><\/div><div class=\"content-holder row m-0 p-0 aling-items-center pt-5 pb-5 \"><div class=\"row  large--swipper-content p-0 \"><div class=\"\"><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Transition to school in the first quarter of the 21st Century: Foundations, research and policy<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Transition Research in Chile: Discussion for Policy and Practice<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-3-032-10435-9<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 189, hasta la p\u00e1gina 206<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Springer<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Sue Dockett, Bob Perry<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Daniela Sof\u00eda Jadue Roa, Mayer Javiera Soto Sarmiento, Thierry Amigo L\u00f3pez<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Transition to school in the first quarter of the 21st Century: Foundations, research and policy<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Transition Research in Chile: Discussion for Policy and Practice<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-3-032-10435-9<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 189, hasta la p\u00e1gina 206<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Springer<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Sue Dockett, Bob Perry<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Daniela Sof\u00eda Jadue Roa, Mayer Javiera Soto Sarmiento, Thierry Amigo L\u00f3pez<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Changing Perspectives: Towards Linguistic Diversity in Education<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Language learning, identity, and interaction:  Findings from multicultural educational contexts in Chile.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 23, hasta la p\u00e1gina 42<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Springer<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Stopfner, M; Guarda, M; Meier, G.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carolina P\u00e9rez Arredondo<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Changing Perspectives: Towards Linguistic Diversity in Education<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Language learning, identity, and interaction:  Findings from multicultural educational contexts in Chile.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 23, hasta la p\u00e1gina 42<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Springer<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Stopfner, M; Guarda, M; Meier, G.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carolina P\u00e9rez Arredondo<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Mathematics Teacher Noticing in Latin America<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Elementary School Teachers\u0092 Attending to Students\u0092 Algebraic Thinking working with Number Sentences<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Springer<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Horacio Solar; Diana Zakaryan; Eder Pinto<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Eder Antonio Pinto Mar\u00edn, Mar\u00eda C. Ca\u00f1adas<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Mathematics Teacher Noticing in Latin America<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Elementary School Teachers\u0092 Attending to Students\u0092 Algebraic Thinking working with Number Sentences<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Springer<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Horacio Solar; Diana Zakaryan; Eder Pinto<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Eder Antonio Pinto Mar\u00edn, Mar\u00eda C. Ca\u00f1adas<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Mathematics Teacher Noticing in Latin America<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">The development of professional noticing of number sense in deaf children<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Spinger<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Horacio Solar; Diana Zakaryan; Eder Pinto<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Juan Luis Pi\u00f1eiro Garrido, Ximena Acu\u00f1a Robertson, Eder Antonio Pinto Mar\u00edn<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Mathematics Teacher Noticing in Latin America<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2026<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">The development of professional noticing of number sense in deaf children<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Spinger<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Horacio Solar; Diana Zakaryan; Eder Pinto<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Juan Luis Pi\u00f1eiro Garrido, Ximena Acu\u00f1a Robertson, Eder Antonio Pinto Mar\u00edn<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> In Light and Shadow: A Photographic History from Indigenous America<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Mapuche photography<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9780762482467<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 232, hasta la p\u00e1gina 233<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Black Dog & Leventhal<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Brian Adams, Sarah Stacke<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Jos\u00e9 Israel Mela Contreras<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> In Light and Shadow: A Photographic History from Indigenous America<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Mapuche photography<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9780762482467<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 232, hasta la p\u00e1gina 233<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Black Dog & Leventhal<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Brian Adams, Sarah Stacke<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Jos\u00e9 Israel Mela Contreras<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> DESARROLLO DE HABILIDADES EN EL AULA DE MATEM\u00c1TICAS<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">El ciclo de investigaci\u00f3n estad\u00edstica: una estrategia para integrar habilidades matem\u00e1ticas y estad\u00edsticas<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad de O'Higgins<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Valentina Sof\u00eda Giaconi Smoje, Francisca Ubilla, Felipe Ruz<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> DESARROLLO DE HABILIDADES EN EL AULA DE MATEM\u00c1TICAS<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">El ciclo de investigaci\u00f3n estad\u00edstica: una estrategia para integrar habilidades matem\u00e1ticas y estad\u00edsticas<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad de O'Higgins<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Valentina Sof\u00eda Giaconi Smoje, Francisca Ubilla, Felipe Ruz<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Cuerpos y territorios en la Investigaci\u00f3n Art\u00edstica<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Retratos de la desterritorializaci\u00f3n materna en pandemia<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 160, hasta la p\u00e1gina 179<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Editorial Universidad de la Rep\u00fablica de Uruguay.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Rosario de Lourdes Garc\u00eda-Huidobro Munita<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Cuerpos y territorios en la Investigaci\u00f3n Art\u00edstica<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Retratos de la desterritorializaci\u00f3n materna en pandemia<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 160, hasta la p\u00e1gina 179<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Editorial Universidad de la Rep\u00fablica de Uruguay.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Rosario de Lourdes Garc\u00eda-Huidobro Munita<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Early language education in instructed contexts: Current issues and empirical insights into teaching and learning languages in primary school<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Primary school learners benefit from captioned video viewing: Vocabulary learning, viewing distribution and perceptions.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9789027223449<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 43, hasta la p\u00e1gina 64<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">John Benjamins<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">S. Frisch, K. Glaser<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Daniela Isabel Avello Garc\u00eda, Carmen Mu\u00f1oz Lahoz<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Early language education in instructed contexts: Current issues and empirical insights into teaching and learning languages in primary school<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Primary school learners benefit from captioned video viewing: Vocabulary learning, viewing distribution and perceptions.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9789027223449<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 43, hasta la p\u00e1gina 64<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">John Benjamins<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">S. Frisch, K. Glaser<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Daniela Isabel Avello Garc\u00eda, Carmen Mu\u00f1oz Lahoz<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Foreign Language Learning from Audiovisual Input: The role of original version television<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Vocabulary learning from captioned-video viewing in primary school learners: The influence of word- and context-related factors<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-3-031-91000-5<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 17, hasta la p\u00e1gina 37<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Springer<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">A. Pattemore, F. Gesa<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Daniela Isabel Avello Garc\u00eda, Carmen Mu\u00f1oz Lahoz<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Foreign Language Learning from Audiovisual Input: The role of original version television<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Vocabulary learning from captioned-video viewing in primary school learners: The influence of word- and context-related factors<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-3-031-91000-5<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 17, hasta la p\u00e1gina 37<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Springer<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">A. Pattemore, F. Gesa<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Daniela Isabel Avello Garc\u00eda, Carmen Mu\u00f1oz Lahoz<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Teoria de Bildung: el retorno a una educaci\u00f3n centrada en la persona<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Bildung, Ausbildung, Halbbildung, Unbildung. Variaciones sobre la teor\u00eda humboldtiana de la formaci\u00f3n<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-956-417-090-9<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 31, hasta la p\u00e1gina 53<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Dykinson, S.L.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">F. Murillo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carlos Jos\u00e9 Willatt Herrera<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Teoria de Bildung: el retorno a una educaci\u00f3n centrada en la persona<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Bildung, Ausbildung, Halbbildung, Unbildung. Variaciones sobre la teor\u00eda humboldtiana de la formaci\u00f3n<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-956-417-090-9<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 31, hasta la p\u00e1gina 53<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Dykinson, S.L.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">F. Murillo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carlos Jos\u00e9 Willatt Herrera<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Realities in Phenomenological and Pedagogical Contexts<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">The digital colonisation of the virtual and the persistence of (proto)virtuality in educational settings<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-3-658-47517-8<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 117, hasta la p\u00e1gina 136<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Springer<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">M. Brinkmann, J. Tu&#776;rstig y M. Weber-Spanknebel<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carlos Jos\u00e9 Willatt Herrera, Marc Fabian Buck<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Realities in Phenomenological and Pedagogical Contexts<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2025<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">The digital colonisation of the virtual and the persistence of (proto)virtuality in educational settings<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-3-658-47517-8<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 117, hasta la p\u00e1gina 136<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Springer<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">M. Brinkmann, J. Tu&#776;rstig y M. Weber-Spanknebel<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carlos Jos\u00e9 Willatt Herrera, Marc Fabian Buck<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Routledge Companion to Young Adult Literature<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Young Adult Literature in South America<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">(Aceptado - en proceso de edici\u00f3n)<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Routledge<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Rodhes Cristina et al.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Isabel Ibaceta<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Routledge Companion to Young Adult Literature<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Young Adult Literature in South America<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">(Aceptado - en proceso de edici\u00f3n)<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Routledge<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Rodhes Cristina et al.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Isabel Ibaceta<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Aprendizaje, desarrollo e inclusi\u00f3n para la formaci\u00f3n y la pr\u00e1ctica en aula de educadores y profesores<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Ansiedad, creencias y estereotipos de g\u00e9nero como factores claves en la ense\u00f1anza y aprendizaje de las matem\u00e1ticas: Propuestas de abordaje en la Formaci\u00f3n Inicial\u00a0Docente [aceptado]<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Ediciones UC<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Susana Mendive, Pilar Cox, Jaime Balladares<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Ana Mar\u00eda Espinoza, David Maximiliano G\u00f3mez Rojas, Mar\u00eda In\u00e9s Susperreguy<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Aprendizaje, desarrollo e inclusi\u00f3n para la formaci\u00f3n y la pr\u00e1ctica en aula de educadores y profesores<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Ansiedad, creencias y estereotipos de g\u00e9nero como factores claves en la ense\u00f1anza y aprendizaje de las matem\u00e1ticas: Propuestas de abordaje en la Formaci\u00f3n Inicial\u00a0Docente [aceptado]<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Ediciones UC<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Susana Mendive, Pilar Cox, Jaime Balladares<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Ana Mar\u00eda Espinoza, David Maximiliano G\u00f3mez Rojas, Mar\u00eda In\u00e9s Susperreguy<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Miradas latinoamericanas sobre multimodalidad: Trayectorias, an\u00e1lisis y metodolog\u00edas<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Introducci\u00f3n<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 33, hasta la p\u00e1gina 38<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Ril Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Liliana V\u00e1squez Rocca, Dominique Manghi Haquin, Carolina P\u00e9rez-Arredondo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Liliana V\u00e1squez-Rocca, Dominique Mangui Haquin, Carolina P\u00e9rez Arredondo<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Miradas latinoamericanas sobre multimodalidad: Trayectorias, an\u00e1lisis y metodolog\u00edas<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Introducci\u00f3n<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 33, hasta la p\u00e1gina 38<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Ril Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Liliana V\u00e1squez Rocca, Dominique Manghi Haquin, Carolina P\u00e9rez-Arredondo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Liliana V\u00e1squez-Rocca, Dominique Mangui Haquin, Carolina P\u00e9rez Arredondo<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Miradas latinoamericanas sobre multimodalidad: Trayectorias, an\u00e1lisis y metodolog\u00edas<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Relegitimaci\u00f3n multimodal de la capucha en redes sociales durante la revuelta social (Chile, 2019-2020)<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 267, hasta la p\u00e1gina 292<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Ril Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Liliana V\u00e1squez Rocca, Dominique Manghi Haquin, Carolina P\u00e9rez-Arredondo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Camila C\u00e1rdenas-Neira, Carolina P\u00e9rez Arredondo<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Miradas latinoamericanas sobre multimodalidad: Trayectorias, an\u00e1lisis y metodolog\u00edas<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Relegitimaci\u00f3n multimodal de la capucha en redes sociales durante la revuelta social (Chile, 2019-2020)<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 267, hasta la p\u00e1gina 292<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Ril Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Liliana V\u00e1squez Rocca, Dominique Manghi Haquin, Carolina P\u00e9rez-Arredondo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Camila C\u00e1rdenas-Neira, Carolina P\u00e9rez Arredondo<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Estudios contempor\u00e1neos en el \u00e1mbito del discurso<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Estudios del discurso y pr\u00e1cticas de minorizaci\u00f3n: El enfoque cr\u00edtico como pr\u00e1ctica docente e investigativa<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 495, hasta la p\u00e1gina 520<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Pedro & Joao Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Rodrigo Acosta Pereira; Mar\u00eda Alexandra Guedes Pinto; Mar\u00eda Cristina Arancibia Aguilera<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carolina P\u00e9rez Arredondo<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Estudios contempor\u00e1neos en el \u00e1mbito del discurso<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Estudios del discurso y pr\u00e1cticas de minorizaci\u00f3n: El enfoque cr\u00edtico como pr\u00e1ctica docente e investigativa<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 495, hasta la p\u00e1gina 520<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Pedro & Joao Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Rodrigo Acosta Pereira; Mar\u00eda Alexandra Guedes Pinto; Mar\u00eda Cristina Arancibia Aguilera<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carolina P\u00e9rez Arredondo<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Feminismos y ciencias sociales en Chile: Voces desde sus participantes<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Feminismos en la academia de las ciencias sociales en Chile<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-956-416-695-7<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 13, hasta la p\u00e1gina 21<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Centro de Estudios de Conflicto y Cohesi\u00f3n Social<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Denisse Sep\u00falveda, Manuela Mendoza, Francisca Ortiz, B\u00e1rbara Flores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Manuela Ji Mendoza Horvitz, Denisse Sep\u00falveda, Francisca Ortiz, B\u00e1rbara Flores<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Feminismos y ciencias sociales en Chile: Voces desde sus participantes<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Feminismos en la academia de las ciencias sociales en Chile<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-956-416-695-7<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 13, hasta la p\u00e1gina 21<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Centro de Estudios de Conflicto y Cohesi\u00f3n Social<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Denisse Sep\u00falveda, Manuela Mendoza, Francisca Ortiz, B\u00e1rbara Flores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Manuela Ji Mendoza Horvitz, Denisse Sep\u00falveda, Francisca Ortiz, B\u00e1rbara Flores<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Feminismos y ciencias sociales en Chile: Voces desde sus participantes<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Producci\u00f3n acad\u00e9mica feminista en las escuelas de sociolog\u00eda en Chile<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-956-416-695-7<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 22, hasta la p\u00e1gina 39<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Centro de Estudios de Conflicto y Cohesi\u00f3n Social<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Denisse Sep\u00falveda, Manuela Mendoza, Francisca Ortiz, B\u00e1rbara Flores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">B\u00e1rbara Flores, Denisse Sep\u00falveda, Francisca Ortiz, Manuela Ji Mendoza Horvitz<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Feminismos y ciencias sociales en Chile: Voces desde sus participantes<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Producci\u00f3n acad\u00e9mica feminista en las escuelas de sociolog\u00eda en Chile<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-956-416-695-7<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 22, hasta la p\u00e1gina 39<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Centro de Estudios de Conflicto y Cohesi\u00f3n Social<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Denisse Sep\u00falveda, Manuela Mendoza, Francisca Ortiz, B\u00e1rbara Flores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">B\u00e1rbara Flores, Denisse Sep\u00falveda, Francisca Ortiz, Manuela Ji Mendoza Horvitz<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Critical Perspectives on Refugee and Migrant Integration in Education. Grassroots Narratives from Multiregional Settings<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Inclusive Ways of Educating and Interacting with Migrant Children in a School in Northern Chile: Questions and Contradiction<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9781350452343<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 25, hasta la p\u00e1gina 34<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Bloomsbury Academic<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Marcus Otto, Tania Saeed<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Andrea Monserratt Cort\u00e9s Saavedra<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Critical Perspectives on Refugee and Migrant Integration in Education. Grassroots Narratives from Multiregional Settings<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Inclusive Ways of Educating and Interacting with Migrant Children in a School in Northern Chile: Questions and Contradiction<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9781350452343<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 25, hasta la p\u00e1gina 34<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Bloomsbury Academic<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Marcus Otto, Tania Saeed<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Andrea Monserratt Cort\u00e9s Saavedra<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Docentes investigadores. Epistemes y metodolog\u00edas<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Investigaciones educativas con perspectiva de g\u00e9nero<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 117, hasta la p\u00e1gina 132<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Editorial Edufba<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Rosario de Lourdes Garc\u00eda-Huidobro Munita<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Docentes investigadores. Epistemes y metodolog\u00edas<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Investigaciones educativas con perspectiva de g\u00e9nero<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 117, hasta la p\u00e1gina 132<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Editorial Edufba<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Rosario de Lourdes Garc\u00eda-Huidobro Munita<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Audiovisual input and second language learning<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">The development of L1 and L2 reading skills from captioned video viewing in primary school EFL learners<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9789027246493<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 25, hasta la p\u00e1gina 47<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">John Benjamins<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">C. Mu\u00f1oz, I. Miralpeix<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Daniela Isabel Avello Garc\u00eda, Carmen Mu\u00f1oz Lahoz<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Audiovisual input and second language learning<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">The development of L1 and L2 reading skills from captioned video viewing in primary school EFL learners<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9789027246493<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 25, hasta la p\u00e1gina 47<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">John Benjamins<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">C. Mu\u00f1oz, I. Miralpeix<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Daniela Isabel Avello Garc\u00eda, Carmen Mu\u00f1oz Lahoz<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Early Foreign Language Learning and Teaching: Evidence Versus Wishful Thinking<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Young Learners\u0092 L2 Vocabulary Acquisition Through Extensive Viewing<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9781800418707<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 114, hasta la p\u00e1gina 131<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Multilingual Matters<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">M. Nikolov, S. Letica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carmen Mu\u00f1oz Lahoz, Daniela Isabel Avello Garc\u00eda, Georgia Pujadas<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Early Foreign Language Learning and Teaching: Evidence Versus Wishful Thinking<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Young Learners\u0092 L2 Vocabulary Acquisition Through Extensive Viewing<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9781800418707<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 114, hasta la p\u00e1gina 131<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Multilingual Matters<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">M. Nikolov, S. Letica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carmen Mu\u00f1oz Lahoz, Daniela Isabel Avello Garc\u00eda, Georgia Pujadas<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Bildung jenseits von Krisen? Anfragen und Perspektiven der qualitativen Bildungs- und Biographieforschung<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Bildung zwischen harmonisierender Sch\u00f6nheit und erschu&#776;tternder Erhabenheit. Zur Ambivalenz \u00e4sthetischer Bildungsprozesse<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-3-8474-2710-0<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 191, hasta la p\u00e1gina 205<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Alem\u00e1n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Verlag Barbara Budrich<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">J. Lipkina, A. Epp, T. Fuchs<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carlos Jos\u00e9 Willatt Herrera<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Bildung jenseits von Krisen? Anfragen und Perspektiven der qualitativen Bildungs- und Biographieforschung<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2024<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Bildung zwischen harmonisierender Sch\u00f6nheit und erschu&#776;tternder Erhabenheit. Zur Ambivalenz \u00e4sthetischer Bildungsprozesse<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-3-8474-2710-0<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 191, hasta la p\u00e1gina 205<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Alem\u00e1n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Verlag Barbara Budrich<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">J. Lipkina, A. Epp, T. Fuchs<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carlos Jos\u00e9 Willatt Herrera<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> The Decommodification of Early Childhood Education and Care: Resisting Neoliberalism<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Resisting the Consumentality of Parents<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9781032110301<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 81, hasta la p\u00e1gina 146<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Routledge<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Michel Vandenbroeck, Joanne Lehrer, Linda Mitchell<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Michel Vandenbroeck, Maarit Alasuutari, Kirsti Karila, Jeroen Janssen, Pablo Iv\u00e1n Rup\u00edn Guti\u00e9rrez, Gail Yuen<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> The Decommodification of Early Childhood Education and Care: Resisting Neoliberalism<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Resisting the Consumentality of Parents<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9781032110301<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 81, hasta la p\u00e1gina 146<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Routledge<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Michel Vandenbroeck, Joanne Lehrer, Linda Mitchell<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Michel Vandenbroeck, Maarit Alasuutari, Kirsti Karila, Jeroen Janssen, Pablo Iv\u00e1n Rup\u00edn Guti\u00e9rrez, Gail Yuen<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Affectivity & Learning<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Learning the Teaching Profession in the Practicum: The Role of the Other, Modalities of Appropriation, and Professional Knowledge<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 411, hasta la p\u00e1gina 440<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Spinger<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">P. Fossa & C. Cort\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">C\u00e9sar Maldonado-D\u00edaz, Javier N\u00fa\u00f1ez Moscoso, Catalina N\u00fa\u00f1ez D\u00edaz, Pablo Iv\u00e1n Rup\u00edn Guti\u00e9rrez<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Affectivity & Learning<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Learning the Teaching Profession in the Practicum: The Role of the Other, Modalities of Appropriation, and Professional Knowledge<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 411, hasta la p\u00e1gina 440<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Spinger<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">P. Fossa & C. Cort\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">C\u00e9sar Maldonado-D\u00edaz, Javier N\u00fa\u00f1ez Moscoso, Catalina N\u00fa\u00f1ez D\u00edaz, Pablo Iv\u00e1n Rup\u00edn Guti\u00e9rrez<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Arruinando Chistes: Panorama de los Estudios del Humor y lo C\u00f3mico, V. II.<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">La risa abunda en la boca de los tontos: lo irrisorio en la narrativa para las infancias en Chile en la segunda mitad del siglo xx<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-631-00-05-1<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 307, hasta la p\u00e1gina 330<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">TeseoPress<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Burkart Mara, Fraticelli Damian, V\u00e1rnagy Tom\u00e1s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Isabel Ibaceta<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Arruinando Chistes: Panorama de los Estudios del Humor y lo C\u00f3mico, V. II.<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">La risa abunda en la boca de los tontos: lo irrisorio en la narrativa para las infancias en Chile en la segunda mitad del siglo xx<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-631-00-05-1<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 307, hasta la p\u00e1gina 330<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">TeseoPress<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Burkart Mara, Fraticelli Damian, V\u00e1rnagy Tom\u00e1s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Isabel Ibaceta<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Educaci\u00f3n art\u00edstica en tiempos de emergencia. Proyecto FAE 2022<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Ense\u00f1anza art\u00edstica desde un enfoque territorial para el fortalecimiento de la participaci\u00f3n cultural, identitaria y creativa de las comunidades<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-956-414-172-5<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 7, hasta la p\u00e1gina 15<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">DAEM Puerto Montt<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Juan alegr\u00eda Licuime; Javier Silva Zurita; Ram\u00f3n Munson Vera<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Jos\u00e9 Israel Mela Contreras, Jorge Ferrada, Juan Licuime, Catalina Montenegro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Educaci\u00f3n art\u00edstica en tiempos de emergencia. Proyecto FAE 2022<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Ense\u00f1anza art\u00edstica desde un enfoque territorial para el fortalecimiento de la participaci\u00f3n cultural, identitaria y creativa de las comunidades<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-956-414-172-5<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 7, hasta la p\u00e1gina 15<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">DAEM Puerto Montt<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Juan alegr\u00eda Licuime; Javier Silva Zurita; Ram\u00f3n Munson Vera<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Jos\u00e9 Israel Mela Contreras, Jorge Ferrada, Juan Licuime, Catalina Montenegro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Grietas y provocaciones. Congreso regional INSEA Am\u00e9rica Latina 2021, Cusco; per\u00fa<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Experiencias en educaci\u00f3n art\u00edstica de la regi\u00f3n de O\u0092higgins (chile). voces docentes con enfoque territorial rural y urbano en contexto de estudio realizado en pandemia por Covid-19<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-989-53600-3-1<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 661, hasta la p\u00e1gina 671<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">InSEA Publications Viseu<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Mario Mogrovejo Dom\u00ednguez; Mirian Celeste Martins; Fernando Miranda<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Jos\u00e9 Israel Mela Contreras, Daniela Cobos (Universidad de Chile)<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Grietas y provocaciones. Congreso regional INSEA Am\u00e9rica Latina 2021, Cusco; per\u00fa<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Experiencias en educaci\u00f3n art\u00edstica de la regi\u00f3n de O\u0092higgins (chile). voces docentes con enfoque territorial rural y urbano en contexto de estudio realizado en pandemia por Covid-19<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-989-53600-3-1<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 661, hasta la p\u00e1gina 671<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">InSEA Publications Viseu<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Mario Mogrovejo Dom\u00ednguez; Mirian Celeste Martins; Fernando Miranda<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Jos\u00e9 Israel Mela Contreras, Daniela Cobos (Universidad de Chile)<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Development of writing skills in children in diverse cultural contexts: contributions to teaching and learning<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Writing technique or writing culture? Representations about writing of children and teachers at high achievement schools in Chile<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Springer<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Alina Galvao, Carmen Sotomayor<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Gabriela Elizabeth G\u00f3mez Vera<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Development of writing skills in children in diverse cultural contexts: contributions to teaching and learning<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Writing technique or writing culture? Representations about writing of children and teachers at high achievement schools in Chile<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Springer<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Alina Galvao, Carmen Sotomayor<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Gabriela Elizabeth G\u00f3mez Vera<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Mathematical learning and cognition in middle childhood and early adolescence: Integrating interdisciplinary research into practice<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Obstacles in the development of the understanding of fractions<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Springer<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Robinson, Kotsopoulos, Dub\u00e9<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Florence Gabriel, Jo Van Hoof, David Maximiliano G\u00f3mez Rojas, Wim Van Dooren<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Mathematical learning and cognition in middle childhood and early adolescence: Integrating interdisciplinary research into practice<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Obstacles in the development of the understanding of fractions<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Springer<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Robinson, Kotsopoulos, Dub\u00e9<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Florence Gabriel, Jo Van Hoof, David Maximiliano G\u00f3mez Rojas, Wim Van Dooren<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Multimodality Studies in International Contexts Contemporary Trends and Challenges<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Consolidation of Multimodality Studies in Latin America: A Review of Emergent Themes<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Routledge<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Liliana V\u00e1squez Rocca, Natasha Artemeva, Chlo\u00eb Grace Fogarty-Bourget<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carolina P\u00e9rez Arredondo, Camila C\u00e1rdenas-Neira<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Multimodality Studies in International Contexts Contemporary Trends and Challenges<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Consolidation of Multimodality Studies in Latin America: A Review of Emergent Themes<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Routledge<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Liliana V\u00e1squez Rocca, Natasha Artemeva, Chlo\u00eb Grace Fogarty-Bourget<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carolina P\u00e9rez Arredondo, Camila C\u00e1rdenas-Neira<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> El juego de la desigualdad: la influencia de Pierre Bourdieu en Chile<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">\u00bfPor qu\u00e9 es importante hablar de Pierre Bourdieu en Chile?<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-956-9114-30-4<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 27, hasta la p\u00e1gina 38<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Mandr\u00e1gora<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Denisse Sep\u00falveda, Manuela Mendoza<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Manuela Ji Mendoza Horvitz, Denisse Sep\u00falveda<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> El juego de la desigualdad: la influencia de Pierre Bourdieu en Chile<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">\u00bfPor qu\u00e9 es importante hablar de Pierre Bourdieu en Chile?<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-956-9114-30-4<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 27, hasta la p\u00e1gina 38<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Mandr\u00e1gora<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Denisse Sep\u00falveda, Manuela Mendoza<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Manuela Ji Mendoza Horvitz, Denisse Sep\u00falveda<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Digitalisierte Lebenswelten \u0096 Bildungstheoretische Reflexionen<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Studieren unter Bedingungen des Digitalen<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-3-662-66122-2<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 347, hasta la p\u00e1gina 369<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Alem\u00e1n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">J. B. Metzler<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">M. F. Buck, M. Zulaica y Mugica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carlos Jos\u00e9 Willatt Herrera, Marc Fabian Buck<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Digitalisierte Lebenswelten \u0096 Bildungstheoretische Reflexionen<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Studieren unter Bedingungen des Digitalen<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-3-662-66122-2<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 347, hasta la p\u00e1gina 369<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Alem\u00e1n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">J. B. Metzler<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">M. F. Buck, M. Zulaica y Mugica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carlos Jos\u00e9 Willatt Herrera, Marc Fabian Buck<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Investigaci\u00f3n en Educaci\u00f3n Matem\u00e1tica. Homenaje a los profesores Pablo Flores e Isidoro Segovia.<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Aportes te\u00f3ricos a la formaci\u00f3n de profesores desde tesis doctorales y su desarrollo en la educaci\u00f3n matem\u00e1tica en Chile<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9788419312419<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 329, hasta la p\u00e1gina 350<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Octaedro<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Elizabeth Ramos-Rodr\u00edguez, Nielka Rojas Gonzalez, Macarena Valenzuela Molina, Mar\u00eda Victoria Mart\u00ednez Videla<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Investigaci\u00f3n en Educaci\u00f3n Matem\u00e1tica. Homenaje a los profesores Pablo Flores e Isidoro Segovia.<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Aportes te\u00f3ricos a la formaci\u00f3n de profesores desde tesis doctorales y su desarrollo en la educaci\u00f3n matem\u00e1tica en Chile<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9788419312419<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 329, hasta la p\u00e1gina 350<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Octaedro<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Elizabeth Ramos-Rodr\u00edguez, Nielka Rojas Gonzalez, Macarena Valenzuela Molina, Mar\u00eda Victoria Mart\u00ednez Videla<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> M\u00fasica y arte para la calidad de vida: propuestas y experiencias<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Artes y pedagog\u00eda: su rol e impacto para una educaci\u00f3n integral desde una experiencia de narrativa audiovisual<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-84-1122-117-7<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 45-51, hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Dykinson, S.L.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Vernia, Ana Mercedes<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Jos\u00e9 Israel Mela Contreras<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> M\u00fasica y arte para la calidad de vida: propuestas y experiencias<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Artes y pedagog\u00eda: su rol e impacto para una educaci\u00f3n integral desde una experiencia de narrativa audiovisual<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-84-1122-117-7<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 45-51, hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Dykinson, S.L.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Vernia, Ana Mercedes<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Jos\u00e9 Israel Mela Contreras<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Grietas y provocaciones: congreso regional INSEA<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Experiencias en educaci\u00f3n art\u00edstica de la regi\u00f3n de O\u0092Higgins (chile). Voces docentes con enfoque territorial rural y urbano en contexto de estudio realizado en pandemia por covid-19<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 632, hasta la p\u00e1gina 642<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">InSEA Publications Viseu<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Jos\u00e9 Israel Mela Contreras, Daniela Cobos Bustamante<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Grietas y provocaciones: congreso regional INSEA<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Experiencias en educaci\u00f3n art\u00edstica de la regi\u00f3n de O\u0092Higgins (chile). Voces docentes con enfoque territorial rural y urbano en contexto de estudio realizado en pandemia por covid-19<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 632, hasta la p\u00e1gina 642<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">InSEA Publications Viseu<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Jos\u00e9 Israel Mela Contreras, Daniela Cobos Bustamante<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Chilean Spanish Linguistics: Studies on variation, innovation, contact, and identity<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Acquisition of variation in Chilean Spanish: \/s\/ lenition in the speech of young children and their mothers<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Vernon Press<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Brandon Rogers, Mauricio Figueroa<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Miguel Alejandro Ramos Riquelme, Karen Miller<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Chilean Spanish Linguistics: Studies on variation, innovation, contact, and identity<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Acquisition of variation in Chilean Spanish: \/s\/ lenition in the speech of young children and their mothers<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Vernon Press<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Brandon Rogers, Mauricio Figueroa<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Miguel Alejandro Ramos Riquelme, Karen Miller<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> (Re)conceptualising Children\u0092s Rights in Infant-Toddler Care and Education: Transnational conversations<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Fledgling Embeddedness of Child Rights Education into Early Childhood Education and Care Undergraduate Programs in Chile<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-3-031-05218-7<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 29, hasta la p\u00e1gina 40<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Springer<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Frances Press, Sandra Cheeseman<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Marcela Pardo, Daniela Sof\u00eda Jadue Roa<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> (Re)conceptualising Children\u0092s Rights in Infant-Toddler Care and Education: Transnational conversations<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Fledgling Embeddedness of Child Rights Education into Early Childhood Education and Care Undergraduate Programs in Chile<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-3-031-05218-7<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 29, hasta la p\u00e1gina 40<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Springer<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Frances Press, Sandra Cheeseman<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Marcela Pardo, Daniela Sof\u00eda Jadue Roa<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Toward a transnational University: WAC\/WID across borders of language, nation, and discipline<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Afterword. Translingual Lives and Writing Pedagogy: Acculturation, Enculturation, and Emancipation<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-1-64215-152-7<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 261, hasta la p\u00e1gina 278<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">The WAC Clearinghouse & University Press of Colorado<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Jonathan Hall, Bruce Horner<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Toward a transnational University: WAC\/WID across borders of language, nation, and discipline<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Afterword. Translingual Lives and Writing Pedagogy: Acculturation, Enculturation, and Emancipation<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-1-64215-152-7<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 261, hasta la p\u00e1gina 278<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">The WAC Clearinghouse & University Press of Colorado<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Jonathan Hall, Bruce Horner<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Ser madre es un placer<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Retratos y relatos sobre la relaci\u00f3n materna en pandemia. El saber relacional de la urgencia<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 224, hasta la p\u00e1gina 240<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Icaria<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Rosario de Lourdes Garc\u00eda-Huidobro Munita<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Ser madre es un placer<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Retratos y relatos sobre la relaci\u00f3n materna en pandemia. El saber relacional de la urgencia<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 224, hasta la p\u00e1gina 240<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Icaria<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Rosario de Lourdes Garc\u00eda-Huidobro Munita<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> ELT research in action<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">The use of captioned-video viewing to support the development of L2 reading skills<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-1-912588-46-6<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 65, hasta la p\u00e1gina 69<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">IATEFL<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">J. Mackay, T. Wogan<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Daniela Isabel Avello Garc\u00eda<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> ELT research in action<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2022<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">The use of captioned-video viewing to support the development of L2 reading skills<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-1-912588-46-6<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 65, hasta la p\u00e1gina 69<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">IATEFL<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">J. Mackay, T. Wogan<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Daniela Isabel Avello Garc\u00eda<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Mathematical reasoning of children and adults: Teaching and learning from an interdisciplinary approach<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Mental and neural foundations of numerical magnitude<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-3-030-69657-3<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 69, hasta la p\u00e1gina 93<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Springer<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Spinillo, Lautert, Borba<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">David Maximiliano G\u00f3mez Rojas, Nicol\u00e1s Morales<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Mathematical reasoning of children and adults: Teaching and learning from an interdisciplinary approach<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Mental and neural foundations of numerical magnitude<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-3-030-69657-3<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 69, hasta la p\u00e1gina 93<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Springer<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Spinillo, Lautert, Borba<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">David Maximiliano G\u00f3mez Rojas, Nicol\u00e1s Morales<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Diccionario de teor\u00edas narrativas 2<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Periodismo Inmersivo<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 591, hasta la p\u00e1gina 592<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Penguin Random House Grupo Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Lorenzo Vilches Manterola<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carolina P\u00e9rez Arredondo<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Diccionario de teor\u00edas narrativas 2<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Periodismo Inmersivo<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 591, hasta la p\u00e1gina 592<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Penguin Random House Grupo Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Lorenzo Vilches Manterola<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carolina P\u00e9rez Arredondo<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Socio-political polarization and conflict: Discursive approaches<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Polarization and the educational conflict: A linguistic and multimodal approach to the discursive (re)construction of the Chilean student movement in the mainstream media and Facebook<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-0-367-52925-3<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 174, hasta la p\u00e1gina 191<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Routledge<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Laura Filardo-Llamas, Esperanza Morales-L\u00f3pez<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Camila C\u00e1rdenas-Neira, Carolina P\u00e9rez Arredondo<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Socio-political polarization and conflict: Discursive approaches<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Polarization and the educational conflict: A linguistic and multimodal approach to the discursive (re)construction of the Chilean student movement in the mainstream media and Facebook<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-0-367-52925-3<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 174, hasta la p\u00e1gina 191<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Routledge<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Laura Filardo-Llamas, Esperanza Morales-L\u00f3pez<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Camila C\u00e1rdenas-Neira, Carolina P\u00e9rez Arredondo<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Repensando la educaci\u00f3n rural: reflexiones y aportes para en el territorio chileno<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Brechas de ruralidad en educaci\u00f3n primaria en Chile: Evoluci\u00f3n entre los a\u00f1os 2002 y 2017 y su relaci\u00f3n con nivel socioecon\u00f3mico<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad de los Lagos<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Silvia Retamal<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Valentina Sof\u00eda Giaconi Smoje, Karina Maldonado<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Repensando la educaci\u00f3n rural: reflexiones y aportes para en el territorio chileno<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Brechas de ruralidad en educaci\u00f3n primaria en Chile: Evoluci\u00f3n entre los a\u00f1os 2002 y 2017 y su relaci\u00f3n con nivel socioecon\u00f3mico<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad de los Lagos<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Silvia Retamal<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Valentina Sof\u00eda Giaconi Smoje, Karina Maldonado<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Handbook of Spanish Discourse Studies<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Academic literacy and discourse studies<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Routledge<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">I. Carranza, T. van Dijk, C. L\u00f3pez Ferrero<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro, Cecilia Colombi<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Handbook of Spanish Discourse Studies<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Academic literacy and discourse studies<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Routledge<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">I. Carranza, T. van Dijk, C. L\u00f3pez Ferrero<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro, Cecilia Colombi<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Escritura e inclusi\u00f3n en la universidad: Herramientas para docentes<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">De la responsabilidad estudiantil a la universidad letrada<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Editorial Universitaria<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Escritura e inclusi\u00f3n en la universidad: Herramientas para docentes<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">De la responsabilidad estudiantil a la universidad letrada<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Editorial Universitaria<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Teaching and Studying Transnational Composition<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">The unequal distribution of research roles in transnational composition: towards illegitimate peripheral participation<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Modern Language Association<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">C. Donahue; B. Horner<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Teaching and Studying Transnational Composition<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">The unequal distribution of research roles in transnational composition: towards illegitimate peripheral participation<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Modern Language Association<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">C. Donahue; B. Horner<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Multilingual contributions to writing research: Towards an equal academic exchange<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Transformados por la escritura. Experiencias y concepciones de estudiantes universitarios a trav\u00e9s del curr\u00edculum y de las etapas formativas<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">The WAC Clearinghouse<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">N. \u00c1vila Reyes<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro, Fernanda Uribe Gajardo, Soledad Montes, Pablo Lovera Falc\u00f3n, B\u00e1rbara Mora-Aguirre, Enrique Sologuren Ins\u00faa, CLaudia Castro, Mart\u00edn \u00c1lvarez<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Multilingual contributions to writing research: Towards an equal academic exchange<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Transformados por la escritura. Experiencias y concepciones de estudiantes universitarios a trav\u00e9s del curr\u00edculum y de las etapas formativas<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">The WAC Clearinghouse<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">N. \u00c1vila Reyes<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro, Fernanda Uribe Gajardo, Soledad Montes, Pablo Lovera Falc\u00f3n, B\u00e1rbara Mora-Aguirre, Enrique Sologuren Ins\u00faa, CLaudia Castro, Mart\u00edn \u00c1lvarez<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Innovaci\u00f3n Docente e Investigaci\u00f3n en Educaci\u00f3n: Nuevos Enfoques en la Metodolog\u00eda Docente<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Organizaci\u00f3n ret\u00f3rica y problematizaci\u00f3n del Informe de resoluci\u00f3n de problemas por ABP: un estudio de caso<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 905, hasta la p\u00e1gina 916<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Dykinson, S.L.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Barrag\u00e1n, A., Molero, M., Martos, A., Sim\u00f3n, M., V\u00e1zquez, J., P\u00e9rez, M<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Emmy Antonella Gonz\u00e1lez Lillo, Marcela Jarpa Azagra, Carmen L\u00f3pez Ferrero<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Innovaci\u00f3n Docente e Investigaci\u00f3n en Educaci\u00f3n: Nuevos Enfoques en la Metodolog\u00eda Docente<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Organizaci\u00f3n ret\u00f3rica y problematizaci\u00f3n del Informe de resoluci\u00f3n de problemas por ABP: un estudio de caso<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 905, hasta la p\u00e1gina 916<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Dykinson, S.L.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Barrag\u00e1n, A., Molero, M., Martos, A., Sim\u00f3n, M., V\u00e1zquez, J., P\u00e9rez, M<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Emmy Antonella Gonz\u00e1lez Lillo, Marcela Jarpa Azagra, Carmen L\u00f3pez Ferrero<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Ling\u00fc\u00edstica del castellano chileno: Estudios sobre variaci\u00f3n, innovaci\u00f3n, contacto e identida<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">El habla sincronizada como dispositivo para la producci\u00f3n del ritmo del espa\u00f1ol como L2<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Vernon Press<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Rogers, B.M., Figueroa, M.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Karina Ester Cerda O\u00f1ate, Francisco Antonio Nocetti, Gloria Toledo Vega, Hern\u00e1n E. P\u00e9rez<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Ling\u00fc\u00edstica del castellano chileno: Estudios sobre variaci\u00f3n, innovaci\u00f3n, contacto e identida<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">El habla sincronizada como dispositivo para la producci\u00f3n del ritmo del espa\u00f1ol como L2<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Vernon Press<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Rogers, B.M., Figueroa, M.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Karina Ester Cerda O\u00f1ate, Francisco Antonio Nocetti, Gloria Toledo Vega, Hern\u00e1n E. P\u00e9rez<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Estallido Social en Chile. Lecturas sobre Educaci\u00f3n y desigualdad en Chile. \"Desigualdad y discriminaci\u00f3n educativa en Chile.<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Nuevos desaf\u00edos territoriales para las universidades. Equidad en acceso y formaciones libres de estereotipos<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 63, hasta la p\u00e1gina 77<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Ediciones Universidad Tecnol\u00f3gica Metropolitana.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Rosario de Lourdes Garc\u00eda-Huidobro Munita<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Estallido Social en Chile. Lecturas sobre Educaci\u00f3n y desigualdad en Chile. \"Desigualdad y discriminaci\u00f3n educativa en Chile.<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2021<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Nuevos desaf\u00edos territoriales para las universidades. Equidad en acceso y formaciones libres de estereotipos<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 63, hasta la p\u00e1gina 77<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Ediciones Universidad Tecnol\u00f3gica Metropolitana.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Rosario de Lourdes Garc\u00eda-Huidobro Munita<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Dos cruces y mil subjetividades<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Territorialidad, pr\u00e1cticas art\u00edsticas y resignificaci\u00f3n de la cultura y sus relatos<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-956-402-553-7<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 34, hasta la p\u00e1gina 34<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad de los Lagos<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Rosario Garc\u00eda Huidobro y Gabriel Hoecker<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Jos\u00e9 Israel Mela Contreras<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Dos cruces y mil subjetividades<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Territorialidad, pr\u00e1cticas art\u00edsticas y resignificaci\u00f3n de la cultura y sus relatos<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-956-402-553-7<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 34, hasta la p\u00e1gina 34<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad de los Lagos<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Rosario Garc\u00eda Huidobro y Gabriel Hoecker<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Jos\u00e9 Israel Mela Contreras<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Antolog\u00eda del Aprendizaje L\u00fadico<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">JUGAR CARTAS PARA APRENDER FUNCIONES EXPONENCIALES<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Alianza ERO-NEXO-Observatorio del Juego<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Jairo Alfredo Navarrete Ulloa<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Antolog\u00eda del Aprendizaje L\u00fadico<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">JUGAR CARTAS PARA APRENDER FUNCIONES EXPONENCIALES<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Alianza ERO-NEXO-Observatorio del Juego<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Jairo Alfredo Navarrete Ulloa<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> G\u00e9neros Textuales\/Discusivos Acad\u00e9micos<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Postfacio: \u00bfEs momento de abandonar los g\u00e9neros discursivos?<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad Nacional de C\u00f3rdoba<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">R. Brunel Matias, V. Cristov\u00e3o, E. Lousada<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> G\u00e9neros Textuales\/Discusivos Acad\u00e9micos<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Postfacio: \u00bfEs momento de abandonar los g\u00e9neros discursivos?<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad Nacional de C\u00f3rdoba<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">R. Brunel Matias, V. Cristov\u00e3o, E. Lousada<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Tesol Spain collected papers<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Content assessment: The blind spot of bilingual programs<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-84-09-28338-5<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 17, hasta la p\u00e1gina 22<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Tesol Spain<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">R. Place, B. Strotmann, K. Marriage, H. Plass<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Daniela Isabel Avello Garc\u00eda<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Tesol Spain collected papers<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Content assessment: The blind spot of bilingual programs<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-84-09-28338-5<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 17, hasta la p\u00e1gina 22<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Tesol Spain<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">R. Place, B. Strotmann, K. Marriage, H. Plass<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Daniela Isabel Avello Garc\u00eda<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Berlin-Brandenburger Beitr\u00e4ge zur Bildungsforschung 2020<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Ph\u00e4nomenologie der \u00e4sthetischen Bildung. Zur temporalen Dimension \u00e4sthetischer Erfahrung<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-3-631-71837-7<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 165, hasta la p\u00e1gina 188<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Alem\u00e1n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Peter Lang<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">J. Stiller, C. Laschke, T. Nesyba, U. Salaschek<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carlos Jos\u00e9 Willatt Herrera<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Berlin-Brandenburger Beitr\u00e4ge zur Bildungsforschung 2020<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2020<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Ph\u00e4nomenologie der \u00e4sthetischen Bildung. Zur temporalen Dimension \u00e4sthetischer Erfahrung<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-3-631-71837-7<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 165, hasta la p\u00e1gina 188<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Alem\u00e1n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Peter Lang<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">J. Stiller, C. Laschke, T. Nesyba, U. Salaschek<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carlos Jos\u00e9 Willatt Herrera<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Listening to children\u0092s advice about starting school and school age care<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Children&#8217;s agency in transition experiences: Understanding possibilities and challenges<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9780815352440<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 26, hasta la p\u00e1gina 41<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">EECERA book series: Towards an Ethical Praxis in Early Childhood: From Research into Practice<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Sue Dockett, J\u00f3hanna Einarsd\u00f3ttir, Bob Perry<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Daniela Sof\u00eda Jadue Roa<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Ethical and Inclusive Research with Children<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Ethical issues in listening to young children in visual participatory research<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9781138334502<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Routledge<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Roseanna Bourke<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Daniela Sof\u00eda Jadue Roa<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Propuestas para Chile 2018<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Juego guiado y educaci\u00f3n parvularia: Propuestas para una mejor calidad de la educaci\u00f3n inicial<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Pontificia Universidad Cat\u00f3lica de Chile<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Valeska Grau, David Preiss, Katherine Strasser, Daniela Sof\u00eda Jadue Roa, Magdalena M\u00fcller, Amaya Lorca<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> The Routledge International Handbook of Young Children\u0092s Rights<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Young Children\u0092s Right to Play during their Transition from Early Childhood Education to Primary School in Chile<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9780367142018<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 535, hasta la p\u00e1gina 551<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Routledge<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Jane Murray, Beth Blue Swadener, Kylie Smith<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Daniela Sof\u00eda Jadue Roa, Mat\u00edas Knust<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Listening to children\u0092s advice about starting school and school age care<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Children&#8217;s agency in transition experiences: Understanding possibilities and challenges<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9780815352440<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 26, hasta la p\u00e1gina 41<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">EECERA book series: Towards an Ethical Praxis in Early Childhood: From Research into Practice<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Sue Dockett, J\u00f3hanna Einarsd\u00f3ttir, Bob Perry<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Daniela Sof\u00eda Jadue Roa<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Ethical and Inclusive Research with Children<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Ethical issues in listening to young children in visual participatory research<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9781138334502<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Routledge<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Roseanna Bourke<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Daniela Sof\u00eda Jadue Roa<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Propuestas para Chile 2018<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Juego guiado y educaci\u00f3n parvularia: Propuestas para una mejor calidad de la educaci\u00f3n inicial<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Pontificia Universidad Cat\u00f3lica de Chile<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Valeska Grau, David Preiss, Katherine Strasser, Daniela Sof\u00eda Jadue Roa, Magdalena M\u00fcller, Amaya Lorca<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> The Routledge International Handbook of Young Children\u0092s Rights<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Young Children\u0092s Right to Play during their Transition from Early Childhood Education to Primary School in Chile<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9780367142018<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 535, hasta la p\u00e1gina 551<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Routledge<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Jane Murray, Beth Blue Swadener, Kylie Smith<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Daniela Sof\u00eda Jadue Roa, Mat\u00edas Knust<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Discourses from Latin America and the Caribbean: Current Concepts and Challenges<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Introduction<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-0-367-52925-3<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Palgrave Macmillan<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Eleonora Esposito, Carolina P\u00e9rez-Arredondo; Jos\u00e9 Manuel Ferreiro<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Eleonora Esposito, Carolina P\u00e9rez Arredondo, Jos\u00e9 Manuel Ferreiro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Discourses from Latin America and the Caribbean: Current Concepts and Challenges<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Introduction<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-0-367-52925-3<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Palgrave Macmillan<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Eleonora Esposito, Carolina P\u00e9rez-Arredondo; Jos\u00e9 Manuel Ferreiro<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Eleonora Esposito, Carolina P\u00e9rez Arredondo, Jos\u00e9 Manuel Ferreiro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Discourses from Latin America and the Caribbean: Current Concepts and Challenges<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">The hooded student as a metaphor: Multimodal recontextualizations of the Chilean Student Movement in a broadcast news report<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-0-367-52925-3<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 107, hasta la p\u00e1gina 138<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Palgrave Macmillan<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Eleonora Esposito, Carolina P\u00e9rez-Arredondo; Jos\u00e9 Manuel Ferreiro<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carolina P\u00e9rez Arredondo, Camila C\u00e1rdenas-Neira<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Discourses from Latin America and the Caribbean: Current Concepts and Challenges<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">The hooded student as a metaphor: Multimodal recontextualizations of the Chilean Student Movement in a broadcast news report<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-0-367-52925-3<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 107, hasta la p\u00e1gina 138<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Palgrave Macmillan<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Eleonora Esposito, Carolina P\u00e9rez-Arredondo; Jos\u00e9 Manuel Ferreiro<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carolina P\u00e9rez Arredondo, Camila C\u00e1rdenas-Neira<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Hablar, persuadir y aprender: Manual para la comunicaci\u00f3n oral en contextos acad\u00e9micos<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Hablar, dialogar, persuadir: ret\u00f3rica de la comunicaci\u00f3n oral en contextos acad\u00e9micos<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-956-19-1156-7<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 16, hasta la p\u00e1gina 27<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad de Chile<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">S. Montes; F. Navarro<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Soledad Montes, Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Hablar, persuadir y aprender: Manual para la comunicaci\u00f3n oral en contextos acad\u00e9micos<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Hablar, dialogar, persuadir: ret\u00f3rica de la comunicaci\u00f3n oral en contextos acad\u00e9micos<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-956-19-1156-7<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 16, hasta la p\u00e1gina 27<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad de Chile<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">S. Montes; F. Navarro<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Soledad Montes, Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> De la Reforma a la Transformaci\u00f3n: Capacidades, Innovaciones y Regulaci\u00f3n de la Educaci\u00f3n Chilena<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">El nuevo sistema de admisi\u00f3n escolar: \u00bfConviene Reformarlo?<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Ediciones UC<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Carrasco, & Flores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Alejandro Carrasco, Ngaire Noelle Honey, Juan de Dios Oyarz\u00fan, Ang\u00e9lica Bonilla<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> De la Reforma a la Transformaci\u00f3n: Capacidades, Innovaciones y Regulaci\u00f3n de la Educaci\u00f3n Chilena<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">El nuevo sistema de admisi\u00f3n escolar: \u00bfConviene Reformarlo?<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Ediciones UC<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Carrasco, & Flores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Alejandro Carrasco, Ngaire Noelle Honey, Juan de Dios Oyarz\u00fan, Ang\u00e9lica Bonilla<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> P\u00e4dagogik im Verborgenen. Bildung und Erziehung in der \u00e4sthetischen Gegenwart<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Das P\u00e4dagogische im Schatten der \u00e4sthetischen Differenz<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-3-658-21890-4<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 27, hasta la p\u00e1gina 44<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Alem\u00e1n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Springer<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">C. Bach<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carlos Jos\u00e9 Willatt Herrera<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> P\u00e4dagogik im Verborgenen. Bildung und Erziehung in der \u00e4sthetischen Gegenwart<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2019<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Das P\u00e4dagogische im Schatten der \u00e4sthetischen Differenz<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-3-658-21890-4<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 27, hasta la p\u00e1gina 44<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Alem\u00e1n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Springer<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">C. Bach<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carlos Jos\u00e9 Willatt Herrera<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Ense\u00f1ar Matem\u00e1ticas. Homenaje a los profesores Francisco Fern\u00e1ndez y Francisco Ruiz<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">La resoluci\u00f3n de problemas de final abierto en el aula de primaria y el cambio del profesor<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-84-96101-68-8<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 187, hasta la p\u00e1gina 202<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Atrio<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Flores, P., Lupi\u00e1\u00f1ez, J.L., Segovia, I.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Victoria Mart\u00ednez Videla, Leonor Varas<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Ense\u00f1ar Matem\u00e1ticas. Homenaje a los profesores Francisco Fern\u00e1ndez y Francisco Ruiz<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">La resoluci\u00f3n de problemas de final abierto en el aula de primaria y el cambio del profesor<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-84-96101-68-8<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 187, hasta la p\u00e1gina 202<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Atrio<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Flores, P., Lupi\u00e1\u00f1ez, J.L., Segovia, I.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Victoria Mart\u00ednez Videla, Leonor Varas<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Territorios Alternos: di\u00e1logos<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Ejercicios de autorrepresentaci\u00f3n mapuche urbana<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-956-398-163-6<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 46-57, hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Pehu\u00e9n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">M\u00f3nica Bengoa; Francisco Schwember<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Jos\u00e9 Israel Mela Contreras<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Territorios Alternos: di\u00e1logos<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Ejercicios de autorrepresentaci\u00f3n mapuche urbana<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-956-398-163-6<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 46-57, hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Pehu\u00e9n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">M\u00f3nica Bengoa; Francisco Schwember<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Jos\u00e9 Israel Mela Contreras<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Actas del X Congreso Internacional de Historia de la Lengua Espa\u00f1ola CIHLE 2015<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">[Publicaci\u00f3n en Actas de Congreso Internacional] Expresi\u00f3n variable de los pronombres de sujeto: diferencias entre \u00e9l y ella<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-84-9911-500-9<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 931-948, hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Instituci\u00f3n Fernando el Cat\u00f3lico<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Mar\u00eda Luisa Arnal Purroy, Rosa Mar\u00eda Casta\u00f1er Mart\u00edn, Jos\u00e9 Mar\u00eda Enguita Utrilla, Vicente Lag\u00fc\u00e9ns Gracia, Mar\u00eda Antonia Mart\u00edn Zorraquino<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Rena Torres Cacoullos, Miguel Alejandro Ramos Riquelme<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Actas del X Congreso Internacional de Historia de la Lengua Espa\u00f1ola CIHLE 2015<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">[Publicaci\u00f3n en Actas de Congreso Internacional] Expresi\u00f3n variable de los pronombres de sujeto: diferencias entre \u00e9l y ella<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-84-9911-500-9<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 931-948, hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Instituci\u00f3n Fernando el Cat\u00f3lico<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Mar\u00eda Luisa Arnal Purroy, Rosa Mar\u00eda Casta\u00f1er Mart\u00edn, Jos\u00e9 Mar\u00eda Enguita Utrilla, Vicente Lag\u00fc\u00e9ns Gracia, Mar\u00eda Antonia Mart\u00edn Zorraquino<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Rena Torres Cacoullos, Miguel Alejandro Ramos Riquelme<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Discourses of Disorder: Representations of Riots, Strikes and Protests in Language and Image<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Why do they protest? The discursive construction of \u0091motive\u0092 in relation to the Chilean student movement in the national alternative press (2011-2013).<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9781474435444<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Edinburgh University Press.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carolina P\u00e9rez Arredondo<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Discourses of Disorder: Representations of Riots, Strikes and Protests in Language and Image<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Why do they protest? The discursive construction of \u0091motive\u0092 in relation to the Chilean student movement in the national alternative press (2011-2013).<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9781474435444<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Edinburgh University Press.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carolina P\u00e9rez Arredondo<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Escrita na universidade. Panoramas e desafios na Am\u00e9rica Latina<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Brasil, Hispanoam\u00e9rica, Latinoam\u00e9rica: hacia un espacio regional com\u00fan en los estudios de la escritura en educaci\u00f3n superior<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-85-237-1328-7<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 7, hasta la p\u00e1gina 36<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Editora da UFPB<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">R. Celi Mendes Pereira<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Escrita na universidade. Panoramas e desafios na Am\u00e9rica Latina<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Brasil, Hispanoam\u00e9rica, Latinoam\u00e9rica: hacia un espacio regional com\u00fan en los estudios de la escritura en educaci\u00f3n superior<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-85-237-1328-7<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 7, hasta la p\u00e1gina 36<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Editora da UFPB<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">R. Celi Mendes Pereira<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Manual de lectura, escritura y oralidad acad\u00e9micas para ingresantes a la universidad<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Did\u00e1ctica basada en g\u00e9neros discursivos para la lectura, escritura y oralidad acad\u00e9micas<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 13, hasta la p\u00e1gina 23<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad Nacional de Quilmes<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">F. Navarro; G. Aparicio<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Manual de lectura, escritura y oralidad acad\u00e9micas para ingresantes a la universidad<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Did\u00e1ctica basada en g\u00e9neros discursivos para la lectura, escritura y oralidad acad\u00e9micas<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 13, hasta la p\u00e1gina 23<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad Nacional de Quilmes<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">F. Navarro; G. Aparicio<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Manual de lectura, escritura y oralidad en econom\u00eda y administraci\u00f3n<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Did\u00e1ctica basada en g\u00e9neros discursivos para la lectura, escritura y oralidad disciplinares<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-987-558-500-3<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 11, hasta la p\u00e1gina 21<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad Nacional de Quilmes<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">F. Navarro; L. Mari<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Manual de lectura, escritura y oralidad en econom\u00eda y administraci\u00f3n<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Did\u00e1ctica basada en g\u00e9neros discursivos para la lectura, escritura y oralidad disciplinares<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-987-558-500-3<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 11, hasta la p\u00e1gina 21<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad Nacional de Quilmes<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">F. Navarro; L. Mari<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Forma\u00e7\u00e3o de Professores: Ensino, linguagens e tecnologias<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">M\u00e1s all\u00e1 de la alfabetizaci\u00f3n acad\u00e9mica: las funciones de la escritura en educaci\u00f3n superior<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-85-5696-308-6<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 13, hasta la p\u00e1gina 49<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Editora Fi<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">M. A. Alves; V. Iensen Bortoluzzi<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Forma\u00e7\u00e3o de Professores: Ensino, linguagens e tecnologias<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">M\u00e1s all\u00e1 de la alfabetizaci\u00f3n acad\u00e9mica: las funciones de la escritura en educaci\u00f3n superior<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-85-5696-308-6<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 13, hasta la p\u00e1gina 49<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Editora Fi<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">M. A. Alves; V. Iensen Bortoluzzi<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Las voces del PACE<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Shock de escritura<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-956-303-368-7<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 48, hasta la p\u00e1gina 49<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad de Santiago de Chile<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">E. Simonsen<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Las voces del PACE<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Shock de escritura<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-956-303-368-7<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 48, hasta la p\u00e1gina 49<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad de Santiago de Chile<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">E. Simonsen<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Escenarios educativos latinoamericanos. Una mirada desde la universidad<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Hacia una formaci\u00f3n onto-epistemol\u00f3gica de artistas-docentes. Un cruce de experiencias.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-612-46680- 6-7<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 8, hasta la p\u00e1gina 19<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">REDEM<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Rosario de Lourdes Garc\u00eda-Huidobro Munita<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Escenarios educativos latinoamericanos. Una mirada desde la universidad<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2018<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Hacia una formaci\u00f3n onto-epistemol\u00f3gica de artistas-docentes. Un cruce de experiencias.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-612-46680- 6-7<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 8, hasta la p\u00e1gina 19<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">REDEM<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Rosario de Lourdes Garc\u00eda-Huidobro Munita<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Formaci\u00f3n inicial docente en el \u00e1rea de lenguaje: experiencias en Am\u00e9rica Latina<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">La demanda de los est\u00e1ndares para egresados y el curr\u00edculum formativo en las carreras de pedagog\u00eda en lenguaje y comunicaci\u00f3n en Chile<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">1548764132<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 89, hasta la p\u00e1gina 117<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">12 Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Silvia Romero, Soledad Concha<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carmen Sotomayor, Gabriela Elizabeth G\u00f3mez Vera<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Formaci\u00f3n inicial docente en el \u00e1rea de lenguaje: experiencias en Am\u00e9rica Latina<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">La demanda de los est\u00e1ndares para egresados y el curr\u00edculum formativo en las carreras de pedagog\u00eda en lenguaje y comunicaci\u00f3n en Chile<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">1548764132<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 89, hasta la p\u00e1gina 117<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">12 Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Silvia Romero, Soledad Concha<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carmen Sotomayor, Gabriela Elizabeth G\u00f3mez Vera<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Discursos medi\u00e1ticos sobre la diferencia en Am\u00e9rica Latina y Caribe<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">(Contra)Racismo diario y la invisibilizaci\u00f3n del mestizaje: An\u00e1lisis de Anita Tijoux y su construcci\u00f3n como \u0093cara de nana\u0094 en la blog\u00f3sfera de un peri\u00f3dico chileno<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 111, hasta la p\u00e1gina 126<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">: L'Institut de la Comunicaci\u00f3 de la Universitat Aut\u00f2noma de Barcelona<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Tania Hoff, Doris Mart\u00ednez<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carolina P\u00e9rez Arredondo<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Discursos medi\u00e1ticos sobre la diferencia en Am\u00e9rica Latina y Caribe<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">(Contra)Racismo diario y la invisibilizaci\u00f3n del mestizaje: An\u00e1lisis de Anita Tijoux y su construcci\u00f3n como \u0093cara de nana\u0094 en la blog\u00f3sfera de un peri\u00f3dico chileno<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 111, hasta la p\u00e1gina 126<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">: L'Institut de la Comunicaci\u00f3 de la Universitat Aut\u00f2noma de Barcelona<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Tania Hoff, Doris Mart\u00ednez<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Carolina P\u00e9rez Arredondo<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Alfabetizaci\u00f3n disciplinar en la formaci\u00f3n inicial docente. Leer y escribir para aprender<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">De la alfabetizaci\u00f3n acad\u00e9mica a la alfabetizaci\u00f3n disciplinar<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9789561707276<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 7, hasta la p\u00e1gina 15<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Ediciones Universitarias de Valpara\u00edso<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">R. Ib\u00e1\u00f1ez; C. Gonz\u00e1lez<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Alfabetizaci\u00f3n disciplinar en la formaci\u00f3n inicial docente. Leer y escribir para aprender<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">De la alfabetizaci\u00f3n acad\u00e9mica a la alfabetizaci\u00f3n disciplinar<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9789561707276<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 7, hasta la p\u00e1gina 15<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Ediciones Universitarias de Valpara\u00edso<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">R. Ib\u00e1\u00f1ez; C. Gonz\u00e1lez<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> El desarrollo de las competencias b\u00e1sicas en los Estudios Generales<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Piensa globalmente, act\u00faa localmente: c\u00f3mo dise\u00f1ar un curso de escritura acad\u00e9mica para estudiantes que ingresan a la universidad<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-612-47379-1-6<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 103, hasta la p\u00e1gina 134<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Pontificia Universidad Cat\u00f3lica de Per\u00fa<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">P. H. J. Quintanilla; A. Valle<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> El desarrollo de las competencias b\u00e1sicas en los Estudios Generales<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Piensa globalmente, act\u00faa localmente: c\u00f3mo dise\u00f1ar un curso de escritura acad\u00e9mica para estudiantes que ingresan a la universidad<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-612-47379-1-6<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 103, hasta la p\u00e1gina 134<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Pontificia Universidad Cat\u00f3lica de Per\u00fa<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">P. H. J. Quintanilla; A. Valle<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Obras esenciales de M. A. K. Halliday<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Pr\u00f3logo a las Obras Esenciales de M. A. K. Halliday<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-987-749-096-1<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 11, hasta la p\u00e1gina 14<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">EUDEBA & Universidad Nacional del Litoral<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">E. Ghio, F. Navarro, A. Lukin<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Elsa Ghio, Federico Daniel Navarro, Annabelle Lukin<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Obras esenciales de M. A. K. Halliday<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Pr\u00f3logo a las Obras Esenciales de M. A. K. Halliday<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-987-749-096-1<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 11, hasta la p\u00e1gina 14<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">EUDEBA & Universidad Nacional del Litoral<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">E. Ghio, F. Navarro, A. Lukin<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Elsa Ghio, Federico Daniel Navarro, Annabelle Lukin<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Twenty Years Later:  Migrant Youth in North America.<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">NAFTA and immigration: A sociodemographic profile of Mexican Individuals in the U.S. and Mexico across three decades.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">PIERAN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Stella Flores, Ngaire Noelle Honey<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Twenty Years Later:  Migrant Youth in North America.<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2017<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">NAFTA and immigration: A sociodemographic profile of Mexican Individuals in the U.S. and Mexico across three decades.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">PIERAN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Stella Flores, Ngaire Noelle Honey<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Abriendo las puertas del aula. Transformaci\u00f3n de las pr\u00e1cticas docentes<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">\u00bfQu\u00e9 caracteriza a las interacciones pedag\u00f3gicas de las escuelas efectivas chilenas?. Una aproximaci\u00f3n exploratoria.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9789561420052.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 185, hasta la p\u00e1gina 220<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Ediciones UC<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Manzi, J., Garc\u00eda, M.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Ernesto Trevi\u00f1o, Leonor Varas, Godoy Ossa, Felipe, Mar\u00eda Victoria Mart\u00ednez Videla<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Abriendo las puertas del aula. Transformaci\u00f3n de las pr\u00e1cticas docentes<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">\u00bfQu\u00e9 caracteriza a las interacciones pedag\u00f3gicas de las escuelas efectivas chilenas?. Una aproximaci\u00f3n exploratoria.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9789561420052.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 185, hasta la p\u00e1gina 220<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Ediciones UC<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Manzi, J., Garc\u00eda, M.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Ernesto Trevi\u00f1o, Leonor Varas, Godoy Ossa, Felipe, Mar\u00eda Victoria Mart\u00ednez Videla<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Le care dans l\u0092\u00e9ducation pr\u00e9scolaire<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Care, participations parentales et apprentissages dans le pr\u00e9scolaire \u00ab non conventionnel \u00bb, au Chili<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9782875743145<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 135, hasta la p\u00e1gina 156<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Franc\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Peter Lang<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Gilles Broug\u00e8re, Sylvie Rayna<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Pablo Iv\u00e1n Rup\u00edn Guti\u00e9rrez<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Le care dans l\u0092\u00e9ducation pr\u00e9scolaire<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Care, participations parentales et apprentissages dans le pr\u00e9scolaire \u00ab non conventionnel \u00bb, au Chili<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9782875743145<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 135, hasta la p\u00e1gina 156<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Franc\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Peter Lang<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Gilles Broug\u00e8re, Sylvie Rayna<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Pablo Iv\u00e1n Rup\u00edn Guti\u00e9rrez<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Literatura para Infancia, Adolescencia y Juventud: Reflexiones desde los Estudios Literarios<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">El cuerpo del ni\u00f1o en Papelucho de Marcela Paz: voz y cronotopo infantil<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9789561125094<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 65, hasta la p\u00e1gina 80<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Editorial Universitaria<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Andrade Claudia, Ibaceta Isabel, Anah\u00ed Troncoso, Camila Valenzuela<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Isabel Ibaceta<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Literatura para Infancia, Adolescencia y Juventud: Reflexiones desde los Estudios Literarios<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">El cuerpo del ni\u00f1o en Papelucho de Marcela Paz: voz y cronotopo infantil<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9789561125094<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 65, hasta la p\u00e1gina 80<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Editorial Universitaria<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Andrade Claudia, Ibaceta Isabel, Anah\u00ed Troncoso, Camila Valenzuela<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Isabel Ibaceta<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Posing and Solving Mathematical Problems<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Affective Factors and Beliefs About Mathematics of Young Chilean Children: Understanding Cultural Characteristics.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-3-319-28023-3<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 37-51, hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Springer International Publishing<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Felmer P., Pehkonen E., Kilpatrick J.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Valentina Sof\u00eda Giaconi Smoje<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Posing and Solving Mathematical Problems<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Affective Factors and Beliefs About Mathematics of Young Chilean Children: Understanding Cultural Characteristics.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-3-319-28023-3<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 37-51, hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Springer International Publishing<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Felmer P., Pehkonen E., Kilpatrick J.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Valentina Sof\u00eda Giaconi Smoje<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Escribir a trav\u00e9s del Curr\u00edculum. Una gu\u00eda de referencia<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">El movimiento Escribir a trav\u00e9s del Curr\u00edculum y la investigaci\u00f3n y la ense\u00f1anza de la escritura en Latinoam\u00e9rica<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-950-33-1299-5<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 38, hasta la p\u00e1gina 48<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad Nacional de C\u00f3rdoba<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">F. Navarro<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Escribir a trav\u00e9s del Curr\u00edculum. Una gu\u00eda de referencia<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">El movimiento Escribir a trav\u00e9s del Curr\u00edculum y la investigaci\u00f3n y la ense\u00f1anza de la escritura en Latinoam\u00e9rica<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-950-33-1299-5<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 38, hasta la p\u00e1gina 48<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad Nacional de C\u00f3rdoba<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">F. Navarro<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Mercado escolar y oportunidad educacional en Chile: libertad, diversidad y desigualdad<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">La dimensi\u00f3n \u00e9tico-pol\u00edtica de la elecci\u00f3n de escuela: dilemas en familias chilenas de elite<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Ediciones UC<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Corvalan, J., Carrasco, A. & Garcia-Huidobro. J.E.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Manuela Ji Mendoza Horvitz<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Mercado escolar y oportunidad educacional en Chile: libertad, diversidad y desigualdad<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2016<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">La dimensi\u00f3n \u00e9tico-pol\u00edtica de la elecci\u00f3n de escuela: dilemas en familias chilenas de elite<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Ediciones UC<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Corvalan, J., Carrasco, A. & Garcia-Huidobro. J.E.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Manuela Ji Mendoza Horvitz<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Educaci\u00f3n   art\u00edstica:   propuestas, investigaci\u00f3n   y\texperiencias recientes<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">La Investigaci\u00f3n Basada en las Artes. Una aproximaci\u00f3n de su aporte a la Educaci\u00f3n Art\u00edstica en Chile<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-956-357-03-80<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad Alberto Hurtado<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Jos\u00e9 Israel Mela Contreras<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Educaci\u00f3n   art\u00edstica:   propuestas, investigaci\u00f3n   y\texperiencias recientes<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">La Investigaci\u00f3n Basada en las Artes. Una aproximaci\u00f3n de su aporte a la Educaci\u00f3n Art\u00edstica en Chile<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-956-357-03-80<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad Alberto Hurtado<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Jos\u00e9 Israel Mela Contreras<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Lectura y escritura 2: lectura y escritura en el nivel medio<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Programa de Escritura en la Escuela. Aportes para instalar la escritura en las disciplinas<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-987-707-039-2<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 36, hasta la p\u00e1gina 46<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad Nacional de C\u00f3rdoba<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">C. Muse<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro, Andrea Revel Chion<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Lectura y escritura 2: lectura y escritura en el nivel medio<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Programa de Escritura en la Escuela. Aportes para instalar la escritura en las disciplinas<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-987-707-039-2<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 36, hasta la p\u00e1gina 46<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad Nacional de C\u00f3rdoba<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">C. Muse<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro, Andrea Revel Chion<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Contrasting Dynamics in Education Politics of Extremes: School Choice in Finland and Chile<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">School Choice in Chile as a Sociocultural Practice: An Ethnographic Inquiry<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Sense<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Sepp\u00e4nen, P. Sepp\u00e4nen, A. Carrasco, M. Kalalahti, R. Rinne & H. Simola<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Manuela Ji Mendoza Horvitz<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Contrasting Dynamics in Education Politics of Extremes: School Choice in Finland and Chile<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">School Choice in Chile as a Sociocultural Practice: An Ethnographic Inquiry<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Sense<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Sepp\u00e4nen, P. Sepp\u00e4nen, A. Carrasco, M. Kalalahti, R. Rinne & H. Simola<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Manuela Ji Mendoza Horvitz<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Historias de vida en educaci\u00f3n. Voces Silenciadas.<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">El espacio entre Saberes docentes de mujeres artistas-docentes.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 126, hasta la p\u00e1gina 138<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad de Almer\u00eda<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Rosario de Lourdes Garc\u00eda-Huidobro Munita<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Memoria de la II Jornada Acad\u00e9mica de Investigadores chilenos en Europa, Aportes para Chile.<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">El saber docente desde una perspectiva de g\u00e9nero. Un saber relacional<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 17, hasta la p\u00e1gina 30<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Punto rojo libros<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Rosario de Lourdes Garc\u00eda-Huidobro Munita<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Proceedings of the 2nd International Conference of Art, Illustration and Visual Culture in Infant and Primary Education.<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Un relato de experiencia para comprender a la Cultura Visual como estrategia metodol\u00f3gica<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 288, hasta la p\u00e1gina 293<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Blucher<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Rosario de Lourdes Garc\u00eda-Huidobro Munita<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Historias de vida en educaci\u00f3n. Voces Silenciadas.<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">El espacio entre Saberes docentes de mujeres artistas-docentes.<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 126, hasta la p\u00e1gina 138<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad de Almer\u00eda<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Rosario de Lourdes Garc\u00eda-Huidobro Munita<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Memoria de la II Jornada Acad\u00e9mica de Investigadores chilenos en Europa, Aportes para Chile.<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">El saber docente desde una perspectiva de g\u00e9nero. Un saber relacional<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 17, hasta la p\u00e1gina 30<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Punto rojo libros<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Rosario de Lourdes Garc\u00eda-Huidobro Munita<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Proceedings of the 2nd International Conference of Art, Illustration and Visual Culture in Infant and Primary Education.<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2015<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Un relato de experiencia para comprender a la Cultura Visual como estrategia metodol\u00f3gica<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 288, hasta la p\u00e1gina 293<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Blucher<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Rosario de Lourdes Garc\u00eda-Huidobro Munita<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Empires, post-coloniality and interculturality<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2014<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">High performance in reading comprehension in poverty conditions in South America: The case of resilient students in PISA 2009 in Argentina, Chile and Uruguay<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-94-6209-731-5<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 101, hasta la p\u00e1gina 106<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Sense<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Leoncio Vega<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Gabriela Elizabeth G\u00f3mez Vera, Juan Pablo Valenzuela C\u00e9spedes, Carmen Sotomayor<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Empires, post-coloniality and interculturality<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2014<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">High performance in reading comprehension in poverty conditions in South America: The case of resilient students in PISA 2009 in Argentina, Chile and Uruguay<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-94-6209-731-5<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 101, hasta la p\u00e1gina 106<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Sense<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Leoncio Vega<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Gabriela Elizabeth G\u00f3mez Vera, Juan Pablo Valenzuela C\u00e9spedes, Carmen Sotomayor<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Manual de escritura para carreras de humanidades<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2014<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">G\u00e9neros discursivos e ingreso a las culturas disciplinares. Aportes para una did\u00e1ctica de la lectura y la escritura en educaci\u00f3n superior<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-987-3617-25-6<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 29, hasta la p\u00e1gina 52<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad de Buenos Aires<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">F. Navarro<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Manual de escritura para carreras de humanidades<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2014<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">G\u00e9neros discursivos e ingreso a las culturas disciplinares. Aportes para una did\u00e1ctica de la lectura y la escritura en educaci\u00f3n superior<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-987-3617-25-6<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 29, hasta la p\u00e1gina 52<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad de Buenos Aires<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">F. Navarro<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Manual de escritura para carreras de humanidades<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2014<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Lectura y escritura de g\u00e9neros acad\u00e9micos. Conceptos b\u00e1sicos<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-987-3617-25-6<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 55, hasta la p\u00e1gina 100<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad de Buenos Aires<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro, Ana Brown<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Manual de escritura para carreras de humanidades<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2014<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Lectura y escritura de g\u00e9neros acad\u00e9micos. Conceptos b\u00e1sicos<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-987-3617-25-6<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 55, hasta la p\u00e1gina 100<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad de Buenos Aires<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro, Ana Brown<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Fundamentaci\u00f3n, criterios y contextos en investigaci\u00f3n basada en las Artes e Investigaci\u00f3n Art\u00edstica<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2014<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Di\u00e1logos con mujeres artistas, docentes. Transitar entre mi pr\u00e1ctica art\u00edstica y de investigaci\u00f3n acad\u00e9mica<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 265, hasta la p\u00e1gina 280<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad de Granada<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Rosario de Lourdes Garc\u00eda-Huidobro Munita<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Socializar conocimiento n\u00ba 2. Observando a Chile desde la distancia<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2014<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Profesoras de Artes Visuales en Chile. Comprender el tr\u00e1nsito entre la pr\u00e1ctica art\u00edstica y docente, desde experiencias narrativas<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 277, hasta la p\u00e1gina 296<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">RedInche<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Rosario de Lourdes Garc\u00eda-Huidobro Munita<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Fundamentaci\u00f3n, criterios y contextos en investigaci\u00f3n basada en las Artes e Investigaci\u00f3n Art\u00edstica<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2014<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Di\u00e1logos con mujeres artistas, docentes. Transitar entre mi pr\u00e1ctica art\u00edstica y de investigaci\u00f3n acad\u00e9mica<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 265, hasta la p\u00e1gina 280<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad de Granada<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Rosario de Lourdes Garc\u00eda-Huidobro Munita<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Socializar conocimiento n\u00ba 2. Observando a Chile desde la distancia<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2014<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Profesoras de Artes Visuales en Chile. Comprender el tr\u00e1nsito entre la pr\u00e1ctica art\u00edstica y docente, desde experiencias narrativas<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 277, hasta la p\u00e1gina 296<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">RedInche<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Rosario de Lourdes Garc\u00eda-Huidobro Munita<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Actas del Seminario Internacional \u00bfQu\u00e9 leer? \u00bfC\u00f3mo leer? Perspectivas sobre la lectura en la infancia.<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2013<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">La influencia de la lectura y el lenguaje en el proceso de formaci\u00f3n de la identidad \u00e9tnica de los lectores infantiles<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-956-292-429-0<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 169-181, hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Ministerio de Educaci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Isabel Ibaceta<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Actas del Seminario Internacional \u00bfQu\u00e9 leer? \u00bfC\u00f3mo leer? Perspectivas sobre la lectura en la infancia.<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2013<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">La influencia de la lectura y el lenguaje en el proceso de formaci\u00f3n de la identidad \u00e9tnica de los lectores infantiles<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-956-292-429-0<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 169-181, hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Ministerio de Educaci\u00f3n<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Isabel Ibaceta<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Diccionario de nuevas formas de lectura y escritura<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2013<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Comunidad de pr\u00e1ctica, comunidad de aprendizaje, comunidad discursiva, cultura disciplinar<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-84-680-0970-4<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 145, hasta la p\u00e1gina 149<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Red Internacional de Universidades Lectoras & Santillana<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">E. Martos N\u00fa\u00f1ez; M. C. Fern\u00e1nde-F\u00edgares<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Diccionario de nuevas formas de lectura y escritura<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2013<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Comunidad de pr\u00e1ctica, comunidad de aprendizaje, comunidad discursiva, cultura disciplinar<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-84-680-0970-4<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 145, hasta la p\u00e1gina 149<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Red Internacional de Universidades Lectoras & Santillana<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">E. Martos N\u00fa\u00f1ez; M. C. Fern\u00e1nde-F\u00edgares<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> El semillero de la escritura. Las tareas escritas a lo largo de tres carreras de la UNGS<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2013<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Consignas de evaluaci\u00f3n en la carrera de Ingenier\u00eda Industrial: articulaciones entre la formaci\u00f3n universitaria y la inserci\u00f3n profesional<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-987-630-151-0<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 71, hasta la p\u00e1gina 91<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">UNGS<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">L. Natale<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Daniela Stagnaro, Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> El semillero de la escritura. Las tareas escritas a lo largo de tres carreras de la UNGS<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2013<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Consignas de evaluaci\u00f3n en la carrera de Ingenier\u00eda Industrial: articulaciones entre la formaci\u00f3n universitaria y la inserci\u00f3n profesional<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-987-630-151-0<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 71, hasta la p\u00e1gina 91<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">UNGS<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">L. Natale<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Daniela Stagnaro, Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> El semillero de la escritura. Las tareas a lo largo de tres carreras de la UNGS<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2013<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Desarrollo interdisciplinario de pautas de escritura, revisi\u00f3n y evaluaci\u00f3n de textos acad\u00e9mico-profesionales. El caso del Informe Final de Pr\u00e1ctica Profesional Supervisada en Ingenier\u00eda Industrial<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-987-630-151-0<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 173, hasta la p\u00e1gina 204<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">UNGS<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">L. Natale<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro, Franco Chiodi<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> El semillero de la escritura. Las tareas a lo largo de tres carreras de la UNGS<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2013<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Desarrollo interdisciplinario de pautas de escritura, revisi\u00f3n y evaluaci\u00f3n de textos acad\u00e9mico-profesionales. El caso del Informe Final de Pr\u00e1ctica Profesional Supervisada en Ingenier\u00eda Industrial<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-987-630-151-0<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 173, hasta la p\u00e1gina 204<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">UNGS<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">L. Natale<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro, Franco Chiodi<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Languages, Metalanguages, Modalities, Cultures. Functional and Socio-Discursive perspectives<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2013<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Non-evaluative verbal processes and invoked evaluation in academic book reviews. Building bridges between systemic-functional and pragmatic-strategic perspectives<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-989-8060-12-9<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 229, hasta la p\u00e1gina 247<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">ILTEC<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">C. A. M. Gouveia; M. F. Alexandre<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Languages, Metalanguages, Modalities, Cultures. Functional and Socio-Discursive perspectives<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2013<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Non-evaluative verbal processes and invoked evaluation in academic book reviews. Building bridges between systemic-functional and pragmatic-strategic perspectives<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-989-8060-12-9<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 229, hasta la p\u00e1gina 247<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">ILTEC<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">C. A. M. Gouveia; M. F. Alexandre<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Hist\u00f3rias de Vida em Educa\u00e7\u00e3o: a Constru\u00e7\u00e3o do Conhecimento a partir de Hist\u00f3rias de Vida.<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2013<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Construyendo nuestros di\u00e1logos. Experiencias de investigaci\u00f3n con historias de vida<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 166, hasta la p\u00e1gina 196<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universitat de Barcelona.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Rosario de Lourdes Garc\u00eda-Huidobro Munita<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Investigar con j\u00f3venes: \u00bfQu\u00e9 sabemos de los j\u00f3venes como productores de cultura visual?<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2013<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">El Desaf\u00edos de los j\u00f3venes Chilenos como productores de Cultura Visual<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 76, hasta la p\u00e1gina 82<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Pamiela \u0096 Edarte (UPNA\/NUP)<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Rosario de Lourdes Garc\u00eda-Huidobro Munita<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Compartir y dialogar en torno a las experiencias del proceso de investigaci\u00f3n.<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2013<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Situando el lugar del otro en mi investigaci\u00f3n. Trabajar con mujeres chilenas artistas y docentes, como parte de mi propia experiencia<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 26, hasta la p\u00e1gina 31<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">AUTODOC<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Rosario de Lourdes Garc\u00eda-Huidobro Munita<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Hist\u00f3rias de Vida em Educa\u00e7\u00e3o: a Constru\u00e7\u00e3o do Conhecimento a partir de Hist\u00f3rias de Vida.<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2013<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Construyendo nuestros di\u00e1logos. Experiencias de investigaci\u00f3n con historias de vida<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 166, hasta la p\u00e1gina 196<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universitat de Barcelona.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Rosario de Lourdes Garc\u00eda-Huidobro Munita<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Investigar con j\u00f3venes: \u00bfQu\u00e9 sabemos de los j\u00f3venes como productores de cultura visual?<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2013<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">El Desaf\u00edos de los j\u00f3venes Chilenos como productores de Cultura Visual<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 76, hasta la p\u00e1gina 82<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Pamiela \u0096 Edarte (UPNA\/NUP)<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Rosario de Lourdes Garc\u00eda-Huidobro Munita<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Compartir y dialogar en torno a las experiencias del proceso de investigaci\u00f3n.<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2013<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Situando el lugar del otro en mi investigaci\u00f3n. Trabajar con mujeres chilenas artistas y docentes, como parte de mi propia experiencia<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 26, hasta la p\u00e1gina 31<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">AUTODOC<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Mar\u00eda Rosario de Lourdes Garc\u00eda-Huidobro Munita<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Evidencias para Pol\u00edticas P\u00fablicas en Educaci\u00f3n<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2012<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Resiliencia acad\u00e9mica en comprensi\u00f3n lectora. J\u00f3venes chilenos en condiciones de pobreza participantes en OECD-PISA 2001 \u0096 2009<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-956-292-361-3<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 133, hasta la p\u00e1gina 174<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Centro de Estudios MINEDUC<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Gabriela Elizabeth G\u00f3mez Vera, Juan Pablo Valenzuela C\u00e9spedes, Carmen Sotomayor<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Evidencias para Pol\u00edticas P\u00fablicas en Educaci\u00f3n<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2012<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Resiliencia acad\u00e9mica en comprensi\u00f3n lectora. J\u00f3venes chilenos en condiciones de pobreza participantes en OECD-PISA 2001 \u0096 2009<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-956-292-361-3<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 133, hasta la p\u00e1gina 174<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Centro de Estudios MINEDUC<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Gabriela Elizabeth G\u00f3mez Vera, Juan Pablo Valenzuela C\u00e9spedes, Carmen Sotomayor<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Discurso especializado: estudios te\u00f3ricos y aplicados<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2012<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Estudio contrastivo de monograf\u00edas escritas en las carreras de Educaci\u00f3n, Filosof\u00eda, Historia y Letras<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-950-774-221-7<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 151, hasta la p\u00e1gina 168<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad Nacional de Cuyo & Sociedad Argentina de Ling\u00fc\u00edstica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">I. Bosio, V. Castel, G. Ciapuscio, L. Cubo, G. M\u00fcller<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro, Juan Pablo Moris<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Discurso especializado: estudios te\u00f3ricos y aplicados<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2012<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Estudio contrastivo de monograf\u00edas escritas en las carreras de Educaci\u00f3n, Filosof\u00eda, Historia y Letras<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-950-774-221-7<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 151, hasta la p\u00e1gina 168<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Universidad Nacional de Cuyo & Sociedad Argentina de Ling\u00fc\u00edstica<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">I. Bosio, V. Castel, G. Ciapuscio, L. Cubo, G. M\u00fcller<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro, Juan Pablo Moris<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> En carrera: escritura y lectura de textos acad\u00e9micos y profesionales<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2012<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">La cita bibliogr\u00e1fica<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-987-630-119-0<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 179, hasta la p\u00e1gina 192<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">UNGS<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">L. Natale<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> En carrera: escritura y lectura de textos acad\u00e9micos y profesionales<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2012<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">La cita bibliogr\u00e1fica<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-987-630-119-0<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 179, hasta la p\u00e1gina 192<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">UNGS<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">L. Natale<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> En carrera: escritura y lectura de textos acad\u00e9micos y profesionales<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2012<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">La rese\u00f1a acad\u00e9mica<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-987-630-119-0<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 39, hasta la p\u00e1gina 59<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">UNGS<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">L. Natale<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro, Ana Luz Abramovich<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> En carrera: escritura y lectura de textos acad\u00e9micos y profesionales<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2012<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">La rese\u00f1a acad\u00e9mica<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-987-630-119-0<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 39, hasta la p\u00e1gina 59<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">UNGS<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">L. Natale<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro, Ana Luz Abramovich<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Jam\u00e1s tan cerca arremeti\u00f3 tan lejos. Inversiones extraterritoriales, crisis ambiental y acci\u00f3n colectiva en Am\u00e9rica Latina<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2012<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Discursos y estrategias en torno a la sustentabilidad del agua en la regi\u00f3n de O\u0092Higgins<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Ediciones La Tierra<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Ospina, Pablo y Hollenstein, Patric<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Manuela Ji Mendoza Horvitz<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Jam\u00e1s tan cerca arremeti\u00f3 tan lejos. Inversiones extraterritoriales, crisis ambiental y acci\u00f3n colectiva en Am\u00e9rica Latina<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2012<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Discursos y estrategias en torno a la sustentabilidad del agua en la regi\u00f3n de O\u0092Higgins<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Ediciones La Tierra<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Ospina, Pablo y Hollenstein, Patric<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Manuela Ji Mendoza Horvitz<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> La trama social de las pr\u00e1cticas culturales: sociedad y subjetividad en el consumo cultural de los chilenos<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2012<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Edades y consumos culturales: industrias culturales, oferta y diversificaci\u00f3n de mercados<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Ediciones Universidad Alberto Hurtado<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">G\u00fcell, Pedro y Peters, Tom\u00e1s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Manuela Ji Mendoza Horvitz<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> La trama social de las pr\u00e1cticas culturales: sociedad y subjetividad en el consumo cultural de los chilenos<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2012<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Edades y consumos culturales: industrias culturales, oferta y diversificaci\u00f3n de mercados<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Ediciones Universidad Alberto Hurtado<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">G\u00fcell, Pedro y Peters, Tom\u00e1s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Manuela Ji Mendoza Horvitz<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Crossed words: Criticism in scholarly writing<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2011<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Critical act as a functional unit for studying academic conflict. A methodological framework<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-3-0343-0049-0<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 23, hasta la p\u00e1gina 52<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Peter Lang<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">F. Salager-Meyer, B. Lewin<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Crossed words: Criticism in scholarly writing<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2011<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Critical act as a functional unit for studying academic conflict. A methodological framework<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">978-3-0343-0049-0<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 23, hasta la p\u00e1gina 52<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Peter Lang<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">F. Salager-Meyer, B. Lewin<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Federico Daniel Navarro<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Parents, pratiques et savoirs au pr\u00e9scolaire<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2010<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Participations parentales, apprentissages et communaut\u00e9s autour du pr\u00e9scolaire<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9052016836<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 203, hasta la p\u00e1gina 221<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Franc\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Peter Lang<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Gilles Broug\u00e8re<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Pablo Iv\u00e1n Rup\u00edn Guti\u00e9rrez, Gilles Broug\u00e8re<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Parents, pratiques et savoirs au pr\u00e9scolaire<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2010<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Participations parentales, apprentissages et communaut\u00e9s autour du pr\u00e9scolaire<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">9052016836<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 203, hasta la p\u00e1gina 221<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Franc\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Peter Lang<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Gilles Broug\u00e8re<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Pablo Iv\u00e1n Rup\u00edn Guti\u00e9rrez, Gilles Broug\u00e8re<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Espacios de Transculturaci\u00f3n en Am\u00e9rica Latina<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2005<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Abajo, la Distancia, el Mar, Cartagena. Adolfo Couve y la Fundaci\u00f3n M\u00edtica de Am\u00e9rica<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">del Centro de Estudios Culturales Latinoamericanos, Universidad de Chile.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Roberto Aedo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Gabriela Elizabeth G\u00f3mez Vera<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Espacios de Transculturaci\u00f3n en Am\u00e9rica Latina<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2005<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Abajo, la Distancia, el Mar, Cartagena. Adolfo Couve y la Fundaci\u00f3n M\u00edtica de Am\u00e9rica<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina , hasta la p\u00e1gina <\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Espa\u00f1ol<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">del Centro de Estudios Culturales Latinoamericanos, Universidad de Chile.<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\">Roberto Aedo<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Gabriela Elizabeth G\u00f3mez Vera<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>[\/vc_tta_section][vc_tta_section title=&#8221;Contacto&#8221; tab_id=&#8221;contacto&#8221;][\/vc_tta_section][\/vc_tta_tabs][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"featured_media":9003,"template":"","institute_academics":[23],"profile_academics":[22],"class_list":["post-201","academics","type-academics","status-publish","has-post-thumbnail","hentry","institute_academics-instituto-de-ciencias-de-la-educacion","profile_academics-academico"],"rut_academico":"13293897-0","mail_academico":"jose.mela@uoh.cl","n_proyectos":"16","n_publicaciones":"10","n_libros":"1","n_cap_libros":"8","n_otros_libros":"0","acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jos\u00e9 Mela - Instituto de Ciencias de la Educaci\u00f3n<\/title>\n<meta name=\"description\" content=\"Profesor Asociado del Instituto de Ciencias de la Educaci\u00f3n de la Universidad Estatal de O&#039;Higgins.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jos\u00e9 Mela - Instituto de Ciencias de la Educaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Profesor Asociado del Instituto de Ciencias de la Educaci\u00f3n de la Universidad Estatal de O&#039;Higgins.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/academico\/jose-mela\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto de Ciencias de la Educaci\u00f3n\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T10:01:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-content\/uploads\/sites\/13\/2025\/09\/Jose-Mela-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/academico\/jose-mela\/\",\"url\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/academico\/jose-mela\/\",\"name\":\"Jos\u00e9 Mela - Instituto de Ciencias de la Educaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/academico\/jose-mela\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/academico\/jose-mela\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-content\/uploads\/sites\/13\/2025\/09\/Jose-Mela-1.jpg\",\"datePublished\":\"2022-04-29T16:48:19+00:00\",\"dateModified\":\"2026-05-13T10:01:59+00:00\",\"description\":\"Profesor Asociado del Instituto de Ciencias de la Educaci\u00f3n de la Universidad Estatal de O'Higgins.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/academico\/jose-mela\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/academico\/jose-mela\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/academico\/jose-mela\/#primaryimage\",\"url\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-content\/uploads\/sites\/13\/2025\/09\/Jose-Mela-1.jpg\",\"contentUrl\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-content\/uploads\/sites\/13\/2025\/09\/Jose-Mela-1.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/academico\/jose-mela\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Acad\u00e9micos\",\"item\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/academico\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jos\u00e9 Mela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/#website\",\"url\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/\",\"name\":\"Instituto de Ciencias de la Educaci\u00f3n\",\"description\":\"Otro sitio de Sitios de Universidad O&#039;higgins\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jos\u00e9 Mela - Instituto de Ciencias de la Educaci\u00f3n","description":"Profesor Asociado del Instituto de Ciencias de la Educaci\u00f3n de la Universidad Estatal de O'Higgins.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Jos\u00e9 Mela - Instituto de Ciencias de la Educaci\u00f3n","og_description":"Profesor Asociado del Instituto de Ciencias de la Educaci\u00f3n de la Universidad Estatal de O'Higgins.","og_url":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/academico\/jose-mela\/","og_site_name":"Instituto de Ciencias de la Educaci\u00f3n","article_modified_time":"2026-05-13T10:01:59+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-content\/uploads\/sites\/13\/2025\/09\/Jose-Mela-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/academico\/jose-mela\/","url":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/academico\/jose-mela\/","name":"Jos\u00e9 Mela - Instituto de Ciencias de la Educaci\u00f3n","isPartOf":{"@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/academico\/jose-mela\/#primaryimage"},"image":{"@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/academico\/jose-mela\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-content\/uploads\/sites\/13\/2025\/09\/Jose-Mela-1.jpg","datePublished":"2022-04-29T16:48:19+00:00","dateModified":"2026-05-13T10:01:59+00:00","description":"Profesor Asociado del Instituto de Ciencias de la Educaci\u00f3n de la Universidad Estatal de O'Higgins.","breadcrumb":{"@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/academico\/jose-mela\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/academico\/jose-mela\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/academico\/jose-mela\/#primaryimage","url":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-content\/uploads\/sites\/13\/2025\/09\/Jose-Mela-1.jpg","contentUrl":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-content\/uploads\/sites\/13\/2025\/09\/Jose-Mela-1.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/academico\/jose-mela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Acad\u00e9micos","item":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/academico\/"},{"@type":"ListItem","position":2,"name":"Jos\u00e9 Mela"}]},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/#website","url":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/","name":"Instituto de Ciencias de la Educaci\u00f3n","description":"Otro sitio de Sitios de Universidad O&#039;higgins","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-json\/wp\/v2\/academics\/201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-json\/wp\/v2\/academics"}],"about":[{"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-json\/wp\/v2\/types\/academics"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-json\/wp\/v2\/media\/9003"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-json\/wp\/v2\/media?parent=201"}],"wp:term":[{"taxonomy":"institute_academics","embeddable":true,"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-json\/wp\/v2\/institute_academics?post=201"},{"taxonomy":"profile_academics","embeddable":true,"href":"https:\/\/www.uoh.cl\/instituto-de-ciencias-de-la-educacion\/wp-json\/wp\/v2\/profile_academics?post=201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}