
{"id":5487,"date":"2025-03-10T08:51:10","date_gmt":"2025-03-10T11:51:10","guid":{"rendered":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/2025\/03\/10\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\/"},"modified":"2025-03-10T10:31:44","modified_gmt":"2025-03-10T13:31:44","slug":"fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad","status":"publish","type":"post","link":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/2025\/03\/10\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\/","title":{"rendered":"Fernanda Kri Amar, Rectora UOH: \u201cLas mujeres debemos seguir avanzando, liderando y ocupando espacios en todos los \u00e1mbitos de la sociedad\u201d"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row][vc_column]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\"><span itemprop=\"name\">Instituto de Ciencias de la Salud <\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/noticias\/\"><span itemprop=\"name\">Noticias<\/span><\/a><meta itemprop=\"position\" content=\"3\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Fernanda Kri Amar, Rectora UOH: \u201cLas mujeres debemos seguir avanzando, <\/span><meta itemprop=\"position\" content=\"4\" \/><\/ol><\/div><ul class=\"p-0 list-style-none d-inline-block\"><li class=\"p-0\"><a href=https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/category\/institucional\/ class=\"px-1 py-2\">Institucional<\/a><\/li><\/ul><div class=\"date_publish_post\"> \u25cf Lun 10 de Marzo 2025<\/div><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block title--decorator  big\">Fernanda Kri Amar, Rectora UOH: \u201cLas mujeres debemos seguir avanzando, liderando y ocupando espacios en todos los \u00e1mbitos de la sociedad\u201d<\/h1><\/div>[vc_row_inner el_class=&#8221;border-separator m-0&#8243;][vc_column_inner width=&#8221;2\/3&#8243;]<div class=\"author_wp_class\"> Escrito por <span>Universidad de O'Higgins<\/span><\/div>[\/vc_column_inner][vc_column_inner el_class=&#8221;align-items-end-publish&#8221; width=&#8221;1\/3&#8243;]<div class=\"uoh_social_network_component uoh_row col-12 justify-content-end m-0 p-0\"> <div class=\"icon__facebook-share-button\">\n                       <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/2025\/03\/10\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\/\" target=\"_blank\"> <div class=\"icon__facebook-svg\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22.4px\" height=\"48.3px\" viewBox=\"0 0 22.4 48.3\" style=\"overflow:visible;enable-background:new 0 0 22.4 48.3;\" xml:space=\"preserve\">\n                <defs>\n                <\/defs>\n                <path class=\"st0\" d=\"M22.4,15.6h-7.6v-5c0-1.9,1.2-2.3,2.1-2.3c0.9,0,5.4,0,5.4,0V0l-7.4,0C6.6,0,4.8,6.2,4.8,10.1v5.5H0v8.5h4.8\n                    c0,10.9,0,24.1,0,24.1h10c0,0,0-13.3,0-24.1h6.8L22.4,15.6z\"><\/path>\n                <\/svg><\/a><\/div>\n                    <\/div><div class=\"icon__twitter-share-button\">\n                        <div class=\"icon__twitter-svg\"><a target=\"_blank\" href=\"http:\/\/twitter.com\/share?url=https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/2025\/03\/10\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/a><\/div>\n                        <\/div><div class=\"icon__linkedin-share-button\">\n                        <div class=\"icon__linkedin-svg\">\n                        <a target=\"__blank\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/2025\/03\/10\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\/\"><svg enable-background=\"new 0 0 100 100\" height=\"100px\" id=\"Layer_1\" version=\"1.1\" viewBox=\"0 0 100 100\" width=\"100px\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><circle cx=\"50\" cy=\"50\" fill=\"#ccc\" r=\"45\"\/><g id=\"LinkedIn_1_\"><rect fill=\"#FFFFFF\" height=\"24.361\" width=\"7.69\" x=\"31.271\" y=\"43.569\"\/><path d=\"M59.968,43.334c-4.406,0-7.165,2.387-7.677,4.058v-3.823h-8.636c0.109,2.03,0,24.361,0,24.361h8.636    V54.748c0-0.733-0.034-1.465,0.19-1.991c0.594-1.464,1.869-2.985,4.162-2.985c2.998,0,4.361,2.253,4.361,5.552V67.93h8.721V54.384    C69.726,46.839,65.432,43.334,59.968,43.334z\" fill=\"#FFFFFF\"\/><path d=\"M34.973,32.069c-2.839,0-4.696,1.823-4.696,4.229c0,2.361,1.804,4.224,4.589,4.224h0.054    c2.891,0,4.69-1.869,4.69-4.229C39.555,33.888,37.81,32.069,34.973,32.069z\" fill=\"#FFFFFF\"\/><\/g><\/g><\/svg><\/a><\/div>\n\n            <\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_single_image image=&#8221;44530&#8243; img_size=&#8221;full&#8221; add_caption=&#8221;yes&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; css=&#8221;&#8221;][vc_column_text]\u00a0[\/vc_column_text][vc_column_text css=&#8221;&#8221;]<\/p>\n<ul>\n<li><em>Quien dirige actualmente la Universidad de O\u2019Higgins fue galardonada por el Gobierno Regional en el Marco del D\u00eda Internacional de la Mujer, destacando su liderazgo desde la Academia y el aporte que entrega al desarrollo de la regi\u00f3n que cobija a la Casa de Estudios estatal.<\/em><\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_column_text]\u00a0[\/vc_column_text][vc_column_text css=&#8221;&#8221;]El Teatro Regional de Rancagua fue el escenario escogido por el <a href=\"https:\/\/www.goreohiggins.cl\/\">Gobierno Regional de O\u2019Higgins<\/a>, encabezado por Pablo Silva Amaya, para homenajear a 20 mujeres de distintos puntos de la regi\u00f3n, en el marco de la conmemoraci\u00f3n del D\u00eda Internacional de la Mujer, quienes representan el esp\u00edritu, esfuerzo, compromiso y talento de las mujeres en las 33 comunas de O\u2019Higgins.<\/p>\n<p>Una de ellas fue la Rectora de la <a href=\"https:\/\/www.uoh.cl\/\">Universidad de O\u2019Higgins<\/a>, Fernanda Kri Amar, quien -desde la Academia- sigue aportando al crecimiento del territorio regional y el avance de pol\u00edticas con sentido de g\u00e9nero.<\/p>\n<p>\u201cEstoy muy contenta de que, de entre tantas mujeres importantes y destacadas de la regi\u00f3n, me hayan escogido para otorgarme este reconocimiento. Agradecida del Gobierno Regional y muy de acuerdo con lo escuchado en esta jornada, sobre la importancia que tienen y deben seguir teniendo nuestras mujeres en el desarrollo de la regi\u00f3n, en cada municipio y en cada instancia local y regional\u201d, se\u00f1al\u00f3 la autoridad universitaria.<\/p>\n<p>Para la Rectora de la UOH queda mucho por recorrer en este camino de igualdad. \u201cHemos avanzado mucho en equidad de g\u00e9nero, pero todav\u00eda nos falta para tener un cambio cultural de verdad. Eso hace que todos los avances que logremos sean un poco vulnerables a un posible retroceso, especialmente cuando existen cambios en pol\u00edticas y autoridades, como observamos hoy en pa\u00edses vecinos y hacia el norte del continente. Si los cambios no est\u00e1n afirmes, todav\u00eda falta mucho que avanzar. Y para eso necesitamos no solo a las mujeres, sino a la sociedad completa, hombres, mujeres, todas las diversidades participando para lograr esta igualdad\u201d.<\/p>\n<p>Sobre el mensaje que deja una fecha conmemorativa como el D\u00eda Internacional de la Mujer, asegura que est\u00e1 claro: \u201cQue sigamos luchando, que nos acompa\u00f1emos, que estemos siempre apoy\u00e1ndonos, porque es un camino que no es f\u00e1cil; es muy bonito y podemos lograr muchas cosas, pero siempre si trabajamos en conjunto. Lo que estamos haciendo hoy es pavimentar el camino para futuras generaciones y eso no lo podemos dejar de hacer\u201d.<\/p>\n<p>El anfitri\u00f3n de la jornada, el Gobernador Pablo Silva Amaya, destac\u00f3 el trabajo de la Rectora Kri Amar, \u201cespecialmente por su empuje de mujer, que deja muy alto al g\u00e9nero femenino en la direcci\u00f3n de esta joven Universidad, que ha sido muy exitosa\u201d.<\/p>\n<p>Tambi\u00e9n tuvo palabras para los varones: \u201cUn mensaje especialmente a los hombres, debemos dar los espacios correspondientes a las mujeres. En nuestro caso, como gobierno regional, somos paritarios, tenemos una administradora espectacular, una rectora espectacular, una directora del hospital regional excelente, una coronel de Carabineros, hay mucha gente capacitada a la que debemos darle los espacios correspondientes\u201d.[\/vc_column_text][vc_zigzag color=&#8221;white&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;2\/3&#8243;][vc_raw_html css=&#8221;&#8221;]JTNDaWZyYW1lJTIwd2lkdGglM0QlMjI1NjAlMjIlMjBoZWlnaHQlM0QlMjIzMTUlMjIlMjBzcmMlM0QlMjJodHRwcyUzQSUyRiUyRnd3dy55b3V0dWJlLmNvbSUyRmVtYmVkJTJGcVRLblhWTS05QVUlM0ZzaSUzRHFNLUtyamNiZmpjUkI1VDklMjIlMjB0aXRsZSUzRCUyMllvdVR1YmUlMjB2aWRlbyUyMHBsYXllciUyMiUyMGZyYW1lYm9yZGVyJTNEJTIyMCUyMiUyMGFsbG93JTNEJTIyYWNjZWxlcm9tZXRlciUzQiUyMGF1dG9wbGF5JTNCJTIwY2xpcGJvYXJkLXdyaXRlJTNCJTIwZW5jcnlwdGVkLW1lZGlhJTNCJTIwZ3lyb3Njb3BlJTNCJTIwcGljdHVyZS1pbi1waWN0dXJlJTNCJTIwd2ViLXNoYXJlJTIyJTIwcmVmZXJyZXJwb2xpY3klM0QlMjJzdHJpY3Qtb3JpZ2luLXdoZW4tY3Jvc3Mtb3JpZ2luJTIyJTIwYWxsb3dmdWxsc2NyZWVuJTNFJTNDJTJGaWZyYW1lJTNF[\/vc_raw_html][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650255686594{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center p-md-0 pt-5 pb-5&#8243;][vc_column el_class=&#8221;pb-5&#8243;][vc_row_inner el_class=&#8221;pb-5&#8243;][vc_column_inner]<div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0\"><h2 class=\"title title--decorator title--ms d-inline-block\">Te Recomendamos<\/h2><\/div><\/div><div class=\"content-holder\"><div class=\"row  swipper-news-list not--activate-hack \"><div class=\"row -wrapper\"><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/category\/salud\/\">\n                                        Salud<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-content\/uploads\/sites\/26\/2026\/07\/Salud-Apicultores-2-1.jpeg\" alt=\"UOH y Natural Bee impulsan programa que fortalecer\u00e1 la salud laboral de apicultores de O\u2019Higgins\" style=\"--smush-placeholder-width: 1600px; --smush-placeholder-aspect-ratio: 1600\/900;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Mi\u00e9rcoles 1, Julio<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/2026\/07\/01\/uoh-y-natural-bee-impulsan-programa-que-fortalecera-la-salud-laboral-de-apicultores-de-ohiggins\/\">\n                                    <h3 class=\"small-space\">UOH y Natural Bee impulsan programa que fortalecer\u00e1 la salud laboral de apicultores de O\u2019Higgins<\/h3><\/a>\n\n                                    <p>El convenio permitir\u00e1 brindar atenciones gratuitas a productores ap\u00edcolas mediante un trabajo interdisciplinario liderado por la Universidad de O\u2019Higgins.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/2026\/07\/01\/uoh-y-natural-bee-impulsan-programa-que-fortalecera-la-salud-laboral-de-apicultores-de-ohiggins\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/category\/acreditacion\/\">\n                                        Acreditaci\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-content\/uploads\/sites\/26\/2026\/06\/Acreditacion-Mesas-de-trabajo-con-estudiantes-14.jpg\" alt=\"Mesa de Di\u00e1logo Estudiantil reuni\u00f3 voces de la comunidad universitaria en el marco de la Acreditaci\u00f3n 2027\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/882;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Lunes 15, Junio<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/2026\/06\/15\/mesa-de-dialogo-estudiantil-reunio-voces-de-la-comunidad-universitaria-en-el-marco-de-la-acreditacion-2027\/\">\n                                    <h3 class=\"small-space\">Mesa de Di\u00e1logo Estudiantil reuni\u00f3 voces de la comunidad universitaria en el marco de la Acreditaci\u00f3n 2027<\/h3><\/a>\n\n                                    <p>Estudiantes de distintas carreras reflexionaron sobre aquellos aspectos que distinguen a la instituci\u00f3n y tambi\u00e9n sobre las oportunidades de mejora que permitan fortalecer la experiencia universitaria.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/2026\/06\/15\/mesa-de-dialogo-estudiantil-reunio-voces-de-la-comunidad-universitaria-en-el-marco-de-la-acreditacion-2027\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-content\/uploads\/sites\/26\/2026\/06\/Presentacion-PDE-2026-20.jpg\" alt=\"UOH lanza su Plan de Desarrollo Estrat\u00e9gico 2026-2030 con miras a consolidar su cultura de calidad institucional\" style=\"--smush-placeholder-width: 1470px; --smush-placeholder-aspect-ratio: 1470\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Lunes 1, Junio<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/2026\/06\/01\/uoh-lanza-su-plan-de-desarrollo-estrategico-2026-2030-con-miras-a-consolidar-su-cultura-de-calidad-institucional\/\">\n                                    <h3 class=\"small-space\">UOH lanza su Plan de Desarrollo Estrat\u00e9gico 2026-2030 con miras a consolidar su cultura de calidad institucional<\/h3><\/a>\n\n                                    <p>La iniciativa, liderada por la Direcci\u00f3n de Desarrollo Institucional, contempla mecanismos de seguimiento y mejora continua orientados a fortalecer el v\u00ednculo de la Universidad con el territorio y los desaf\u00edos globales.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/2026\/06\/01\/uoh-lanza-su-plan-de-desarrollo-estrategico-2026-2030-con-miras-a-consolidar-su-cultura-de-calidad-institucional\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pagination justify-content-center my-5\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-json\/wp\/v2\/posts\/5487\/\/page\/2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-json\/wp\/v2\/posts\/5487\/\/page\/3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-json\/wp\/v2\/posts\/5487\/\/page\/107\">107<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-json\/wp\/v2\/posts\/5487\/\/page\/2\"><div class=\"icon-pagination-next\"> <?xml version=\"1.0\" ?><svg viewBox=\"0 0 96 96\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><title\/><path d=\"M39.3756,48.0022l30.47-25.39a6.0035,6.0035,0,0,0-7.6878-9.223L26.1563,43.3906a6.0092,6.0092,0,0,0,0,9.2231L62.1578,82.615a6.0035,6.0035,0,0,0,7.6878-9.2231Z\"\/><\/svg> <\/div><\/a><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Quien dirige actualmente la Universidad de O\u2019Higgins fue galardonada por el Gobierno Regional en el Marco del D\u00eda Internacional de la Mujer, destacando su liderazgo desde la Academia y el aporte que entrega al desarrollo de la regi\u00f3n que cobija a la Casa de Estudios estatal.<\/p>\n","protected":false},"author":34,"featured_media":5492,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-5487","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucional"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fernanda Kri Amar, Rectora UOH: \u201cLas mujeres debemos seguir avanzando, liderando y ocupando espacios en todos los \u00e1mbitos de la sociedad\u201d - Instituto de Ciencias de la Salud<\/title>\n<meta name=\"description\" content=\"Quien dirige actualmente la Universidad de O\u2019Higgins fue galardonada por el Gobierno Regional en el Marco del D\u00eda Internacional de la Mujer, destacando su liderazgo desde la Academia y el aporte que entrega al desarrollo de la regi\u00f3n que cobija a la Casa de Estudios estatal.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fernanda Kri Amar, Rectora UOH: \u201cLas mujeres debemos seguir avanzando, liderando y ocupando espacios en todos los \u00e1mbitos de la sociedad\u201d - Instituto de Ciencias de la Salud\" \/>\n<meta property=\"og:description\" content=\"Quien dirige actualmente la Universidad de O\u2019Higgins fue galardonada por el Gobierno Regional en el Marco del D\u00eda Internacional de la Mujer, destacando su liderazgo desde la Academia y el aporte que entrega al desarrollo de la regi\u00f3n que cobija a la Casa de Estudios estatal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/2025\/03\/10\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto de Ciencias de la Salud\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-10T11:51:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-10T13:31:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-content\/uploads\/sites\/26\/2025\/03\/Premio-Rectora-Fernanda-Kri-Amar-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Universidad de O&#039;Higgins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Universidad de O&#039;Higgins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-ciencias-de-la-salud\\\/2025\\\/03\\\/10\\\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-ciencias-de-la-salud\\\/2025\\\/03\\\/10\\\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\\\/\"},\"author\":{\"name\":\"Universidad de O'Higgins\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-ciencias-de-la-salud\\\/#\\\/schema\\\/person\\\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"headline\":\"Fernanda Kri Amar, Rectora UOH: \u201cLas mujeres debemos seguir avanzando, liderando y ocupando espacios en todos los \u00e1mbitos de la sociedad\u201d\",\"datePublished\":\"2025-03-10T11:51:10+00:00\",\"dateModified\":\"2025-03-10T13:31:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-ciencias-de-la-salud\\\/2025\\\/03\\\/10\\\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\\\/\"},\"wordCount\":836,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-ciencias-de-la-salud\\\/2025\\\/03\\\/10\\\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-ciencias-de-la-salud\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2025\\\/03\\\/Premio-Rectora-Fernanda-Kri-Amar-4.jpg\",\"articleSection\":[\"Institucional\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.uoh.cl\\\/instituto-ciencias-de-la-salud\\\/2025\\\/03\\\/10\\\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-ciencias-de-la-salud\\\/2025\\\/03\\\/10\\\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\\\/\",\"url\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-ciencias-de-la-salud\\\/2025\\\/03\\\/10\\\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\\\/\",\"name\":\"Fernanda Kri Amar, Rectora UOH: \u201cLas mujeres debemos seguir avanzando, liderando y ocupando espacios en todos los \u00e1mbitos de la sociedad\u201d - Instituto de Ciencias de la Salud\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-ciencias-de-la-salud\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-ciencias-de-la-salud\\\/2025\\\/03\\\/10\\\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-ciencias-de-la-salud\\\/2025\\\/03\\\/10\\\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-ciencias-de-la-salud\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2025\\\/03\\\/Premio-Rectora-Fernanda-Kri-Amar-4.jpg\",\"datePublished\":\"2025-03-10T11:51:10+00:00\",\"dateModified\":\"2025-03-10T13:31:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-ciencias-de-la-salud\\\/#\\\/schema\\\/person\\\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"description\":\"Quien dirige actualmente la Universidad de O\u2019Higgins fue galardonada por el Gobierno Regional en el Marco del D\u00eda Internacional de la Mujer, destacando su liderazgo desde la Academia y el aporte que entrega al desarrollo de la regi\u00f3n que cobija a la Casa de Estudios estatal.\",\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uoh.cl\\\/instituto-ciencias-de-la-salud\\\/2025\\\/03\\\/10\\\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-ciencias-de-la-salud\\\/2025\\\/03\\\/10\\\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-ciencias-de-la-salud\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2025\\\/03\\\/Premio-Rectora-Fernanda-Kri-Amar-4.jpg\",\"contentUrl\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-ciencias-de-la-salud\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2025\\\/03\\\/Premio-Rectora-Fernanda-Kri-Amar-4.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-ciencias-de-la-salud\\\/#website\",\"url\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-ciencias-de-la-salud\\\/\",\"name\":\"Instituto de Ciencias de la Salud\",\"description\":\"Otro sitio de Sitios de Universidad O'higgins\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-ciencias-de-la-salud\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/instituto-ciencias-de-la-salud\\\/#\\\/schema\\\/person\\\/ea242e676c7d6d7e46fc8b9e39486c4f\",\"name\":\"Universidad de O'Higgins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"caption\":\"Universidad de O'Higgins\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fernanda Kri Amar, Rectora UOH: \u201cLas mujeres debemos seguir avanzando, liderando y ocupando espacios en todos los \u00e1mbitos de la sociedad\u201d - Instituto de Ciencias de la Salud","description":"Quien dirige actualmente la Universidad de O\u2019Higgins fue galardonada por el Gobierno Regional en el Marco del D\u00eda Internacional de la Mujer, destacando su liderazgo desde la Academia y el aporte que entrega al desarrollo de la regi\u00f3n que cobija a la Casa de Estudios estatal.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Fernanda Kri Amar, Rectora UOH: \u201cLas mujeres debemos seguir avanzando, liderando y ocupando espacios en todos los \u00e1mbitos de la sociedad\u201d - Instituto de Ciencias de la Salud","og_description":"Quien dirige actualmente la Universidad de O\u2019Higgins fue galardonada por el Gobierno Regional en el Marco del D\u00eda Internacional de la Mujer, destacando su liderazgo desde la Academia y el aporte que entrega al desarrollo de la regi\u00f3n que cobija a la Casa de Estudios estatal.","og_url":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/2025\/03\/10\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\/","og_site_name":"Instituto de Ciencias de la Salud","article_published_time":"2025-03-10T11:51:10+00:00","article_modified_time":"2025-03-10T13:31:44+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-content\/uploads\/sites\/26\/2025\/03\/Premio-Rectora-Fernanda-Kri-Amar-2.jpg","type":"image\/jpeg"}],"author":"Universidad de O'Higgins","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Universidad de O'Higgins","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/2025\/03\/10\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\/#article","isPartOf":{"@id":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/2025\/03\/10\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\/"},"author":{"name":"Universidad de O'Higgins","@id":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"headline":"Fernanda Kri Amar, Rectora UOH: \u201cLas mujeres debemos seguir avanzando, liderando y ocupando espacios en todos los \u00e1mbitos de la sociedad\u201d","datePublished":"2025-03-10T11:51:10+00:00","dateModified":"2025-03-10T13:31:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/2025\/03\/10\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\/"},"wordCount":836,"commentCount":0,"image":{"@id":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/2025\/03\/10\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-content\/uploads\/sites\/26\/2025\/03\/Premio-Rectora-Fernanda-Kri-Amar-4.jpg","articleSection":["Institucional"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/2025\/03\/10\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/2025\/03\/10\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\/","url":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/2025\/03\/10\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\/","name":"Fernanda Kri Amar, Rectora UOH: \u201cLas mujeres debemos seguir avanzando, liderando y ocupando espacios en todos los \u00e1mbitos de la sociedad\u201d - Instituto de Ciencias de la Salud","isPartOf":{"@id":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/2025\/03\/10\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\/#primaryimage"},"image":{"@id":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/2025\/03\/10\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-content\/uploads\/sites\/26\/2025\/03\/Premio-Rectora-Fernanda-Kri-Amar-4.jpg","datePublished":"2025-03-10T11:51:10+00:00","dateModified":"2025-03-10T13:31:44+00:00","author":{"@id":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"description":"Quien dirige actualmente la Universidad de O\u2019Higgins fue galardonada por el Gobierno Regional en el Marco del D\u00eda Internacional de la Mujer, destacando su liderazgo desde la Academia y el aporte que entrega al desarrollo de la regi\u00f3n que cobija a la Casa de Estudios estatal.","inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/2025\/03\/10\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/2025\/03\/10\/fernanda-kri-amar-rectora-uoh-las-mujeres-debemos-seguir-avanzando-liderando-y-ocupando-espacios-en-todos-los-ambitos-de-la-sociedad\/#primaryimage","url":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-content\/uploads\/sites\/26\/2025\/03\/Premio-Rectora-Fernanda-Kri-Amar-4.jpg","contentUrl":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-content\/uploads\/sites\/26\/2025\/03\/Premio-Rectora-Fernanda-Kri-Amar-4.jpg","width":1000,"height":1000},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/#website","url":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/","name":"Instituto de Ciencias de la Salud","description":"Otro sitio de Sitios de Universidad O'higgins","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f","name":"Universidad de O'Higgins","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","caption":"Universidad de O'Higgins"}}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-json\/wp\/v2\/posts\/5487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-json\/wp\/v2\/comments?post=5487"}],"version-history":[{"count":1,"href":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-json\/wp\/v2\/posts\/5487\/revisions"}],"predecessor-version":[{"id":5489,"href":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-json\/wp\/v2\/posts\/5487\/revisions\/5489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-json\/wp\/v2\/media\/5492"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-json\/wp\/v2\/media?parent=5487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-json\/wp\/v2\/categories?post=5487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-json\/wp\/v2\/tags?post=5487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}