
{"id":86,"date":"2022-04-29T09:39:21","date_gmt":"2022-04-29T12:39:21","guid":{"rendered":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/academico\/sebastian-jannas\/"},"modified":"2026-05-13T07:02:40","modified_gmt":"2026-05-13T10:02:40","slug":"sebastian-jannas","status":"publish","type":"academics","link":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/academico\/sebastian-jannas\/","title":{"rendered":"Sebasti\u00e1n Jannas"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1650056176159{padding-top: 3rem !important;}&#8221;][vc_row][vc_column][vc_wp_custommenu nav_menu=&#8221;5&#8243;]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\"><span itemprop=\"name\">Instituto de Ciencias de la Salud <\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/investigacion\"><span itemprop=\"name\">Investigaci\u00f3n<\/span><\/a><meta itemprop=\"position\" content=\"3\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/investigacion\/academicos\"><span itemprop=\"name\">Acad\u00e9micos<\/span><\/a><meta itemprop=\"position\" content=\"4\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Sebasti\u00e1n Jannas <\/span><meta itemprop=\"position\" content=\"5\" \/><\/ol><\/div><ul class=\"p-0 list-style-none d-inline-block\"><\/ul><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block big\">Sebasti\u00e1n Jannas<em class=\"position__title\"> <span>\u25cf<\/span> Profesor Asociado<\/em><\/h1><\/div>[vc_row_inner el_class=&#8221;border-separator m-0 mt-4&#8243;][vc_column_inner width=&#8221;1\/6&#8243;]<div class=\"vc_single_image-wrapper vc_box_rounded  vc_box_border_grey\"><img decoding=\"async\" width=\"1000\" height=\"1000\" data-src=\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-content\/uploads\/sites\/26\/2022\/04\/sebastian_jannas.jpg\" class=\"attachment-large size-large wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-content\/uploads\/sites\/26\/2022\/04\/sebastian_jannas.jpg 1000w, https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-content\/uploads\/sites\/26\/2022\/04\/sebastian_jannas-300x300.jpg 300w, https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-content\/uploads\/sites\/26\/2022\/04\/sebastian_jannas-150x150.jpg 150w, https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-content\/uploads\/sites\/26\/2022\/04\/sebastian_jannas-768x768.jpg 768w, https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-content\/uploads\/sites\/26\/2022\/04\/sebastian_jannas-600x600.jpg 600w\" data-sizes=\"(max-width: 1000px) 100vw, 1000px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1000px; --smush-placeholder-aspect-ratio: 1000\/1000;\" \/><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;2\/3&#8243;]<div class=\"block--info\">\n                                <div class=\"sub_title__grade\">Grado Acad\u00e9mico<\/div>\n                                <h3>Doctor en Salud Humana y Ciencias Nutricionales \u2013 University of Guelph, Guelph, Canad\u00e1<\/h3> <\/div><div class=\"block--info\">\n                                <div class=\"sub_title__grade\">T\u00edtulo(s) Profesional<\/div>\n                                <h3>Profesor de Educaci\u00f3n F\u00edsica Deportes y Recreaci\u00f3n \u2013 Universidad Mayor, Chile<\/h3> <\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;]<div class=\"uoh_social_network_component uoh_row col-12 justify-content-end m-0 p-0\"> <div class=\"icon__facebook-share-button\">\n                       <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/academico\/sebastian-jannas\/\" target=\"_blank\"> <div class=\"icon__facebook-svg\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22.4px\" height=\"48.3px\" viewBox=\"0 0 22.4 48.3\" style=\"overflow:visible;enable-background:new 0 0 22.4 48.3;\" xml:space=\"preserve\">\n                <defs>\n                <\/defs>\n                <path class=\"st0\" d=\"M22.4,15.6h-7.6v-5c0-1.9,1.2-2.3,2.1-2.3c0.9,0,5.4,0,5.4,0V0l-7.4,0C6.6,0,4.8,6.2,4.8,10.1v5.5H0v8.5h4.8\n                    c0,10.9,0,24.1,0,24.1h10c0,0,0-13.3,0-24.1h6.8L22.4,15.6z\"><\/path>\n                <\/svg><\/a><\/div>\n                    <\/div><div class=\"icon__twitter-share-button\">\n                        <div class=\"icon__twitter-svg\"><a target=\"_blank\" href=\"http:\/\/twitter.com\/share?url=https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/academico\/sebastian-jannas\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/a><\/div>\n                        <\/div><div class=\"icon__linkedin-share-button\">\n                        <div class=\"icon__linkedin-svg\">\n                        <a target=\"__blank\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/academico\/sebastian-jannas\/\"><svg enable-background=\"new 0 0 100 100\" height=\"100px\" id=\"Layer_1\" version=\"1.1\" viewBox=\"0 0 100 100\" width=\"100px\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><circle cx=\"50\" cy=\"50\" fill=\"#ccc\" r=\"45\"\/><g id=\"LinkedIn_1_\"><rect fill=\"#FFFFFF\" height=\"24.361\" width=\"7.69\" x=\"31.271\" y=\"43.569\"\/><path d=\"M59.968,43.334c-4.406,0-7.165,2.387-7.677,4.058v-3.823h-8.636c0.109,2.03,0,24.361,0,24.361h8.636    V54.748c0-0.733-0.034-1.465,0.19-1.991c0.594-1.464,1.869-2.985,4.162-2.985c2.998,0,4.361,2.253,4.361,5.552V67.93h8.721V54.384    C69.726,46.839,65.432,43.334,59.968,43.334z\" fill=\"#FFFFFF\"\/><path d=\"M34.973,32.069c-2.839,0-4.696,1.823-4.696,4.229c0,2.361,1.804,4.224,4.589,4.224h0.054    c2.891,0,4.69-1.869,4.69-4.229C39.555,33.888,37.81,32.069,34.973,32.069z\" fill=\"#FFFFFF\"\/><\/g><\/g><\/svg><\/a><\/div>\n\n            <\/div><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650239278498{background-color: #ffffff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center&#8221;][vc_column][vc_row_inner][vc_column_inner width=&#8221;5\/6&#8243;]<div class=\"uoh_title_component-container\"><h4 class=\"title title--ms d-inline-block title--decorator  small\">Descripci\u00f3n<\/h4><\/div><p class=\"info-headings mb-2 text-left mt-4 mt-md-2\">Sebasti\u00e1n Jannas Vela es Profesor de Educaci\u00f3n F\u00edsica de la Universidad Mayor, y Doctor en Metabolismo del Ejercicio y la Nutrici\u00f3n de la Universidad de Guelph, Canad\u00e1. Fue acad\u00e9mico en el Laboratorio de Ciencias del Ejercicio de la Facultad de Medicina en la Universidad Finis Terrae. Actualmente es Profesor Asistente en el Instituto de Ciencias de la Salud de la Universidad de O\u2019Higgins. La l\u00ednea de investigaci\u00f3n del Dr. Jannas Vela consiste en comprender las adaptaciones fisiol\u00f3gicas y moleculares que ocurren con el ejercicio f\u00edsico y la nutrici\u00f3n en humanos.<\/p>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650056119592{background-color: #ffffff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5 pb-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-start&#8221;][vc_column width=&#8221;1\/6&#8243; el_class=&#8221;p-0&#8243;]<div class=\"uoh_link_component pe-4 d-inline-block py-1 button_icon inline\"><i class=\"me-2 fas fa-newspaper\" style=\"color: #42a0f8\"><\/i><span>Publicaciones<\/span><\/div><div class=\"wpb_text_column wpb_content_element  citas mb-3 pb-3\"><div class=\"wpb_wrapper\"><p>14<\/p><\/div><\/div><div class=\"uoh_link_component pe-4 d-inline-block py-1 button_icon inline\"><i class=\"me-2 fas fa-project-diagram\" style=\"color: #42a0f8\"><\/i><span>Proyectos<\/span><\/div><div class=\"wpb_text_column wpb_content_element  citas mb-3 pb-3\"><div class=\"wpb_wrapper\"><p>9<\/p><\/div><\/div><div class=\"uoh_link_component pe-4 d-inline-block py-1 button_icon inline\"><i class=\"me-2 fas fa-book-bookmark\" style=\"color: #42a0f8\"><\/i><span>Cap\u00edtulos de Libros<\/span><\/div><div class=\"wpb_text_column wpb_content_element  citas mb-3 pb-3\"><div class=\"wpb_wrapper\"><p>1<\/p><\/div><\/div>[\/vc_column][vc_column width=&#8221;5\/6&#8243;][vc_tta_tabs active_section=&#8221;1&#8243; el_class=&#8221;tabs-inner-academic&#8221;][vc_tta_section title=&#8221;Publicaciones&#8221; tab_id=&#8221;publicaciones&#8221;]<link rel=\"stylesheet\" id=\"font-awesome-css\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.5.1\/css\/all.min.css\" type=\"text\/css\" media=\"all\"><div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0 px-md-0 \"><\/div><\/div>[\/vc_tta_section][vc_tta_section title=&#8221;Proyectos&#8221; tab_id=&#8221;proyectos&#8221;]<link rel=\"stylesheet\" id=\"font-awesome-css\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.5.1\/css\/all.min.css\" type=\"text\/css\" media=\"all\"><div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0 px-md-0 \"><\/div><\/div>[\/vc_tta_section][vc_tta_section title=&#8221;Cap\u00edtulos de Libros&#8221; tab_id=&#8221;cap-libros&#8221;]<link rel=\"stylesheet\" id=\"font-awesome-css\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.5.1\/css\/all.min.css\" type=\"text\/css\" media=\"all\"><div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0 px-md-0 \"><\/div><\/div><div class=\"content-holder row m-0 p-0 aling-items-center pt-5 pb-5 \"><div class=\"row  large--swipper-content p-0 \"><div class=\"\"><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Molecular Nutrition and Mitochondria Metabolic Deficits, Whole-Diet Interventions, and Targeted Nutraceuticals<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Dietary eicosapentaenoic acid and docosahexaenoic acid for mitochondrial biogenesis and dynamics<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 213, hasta la p\u00e1gina 224<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Elsevier<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Sebasti\u00e1n Jorge Jannas Vela, Mauricio Castro-Sepulveda<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"  circle--pattern-bottom-large col-sm-12 col-md-12 img-article\"><div class=\"holder-publish col-md-12\" style=\"border-bottom: 1px solid #B8B8B8\"><div class=\"content-holder h-100 component-border overflow-hidden row m-0 p-4 aling-items-center\"><ul class=\"p-0 list-style-none\"><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-book fa-fw\"><\/i> Molecular Nutrition and Mitochondria Metabolic Deficits, Whole-Diet Interventions, and Targeted Nutraceuticals<\/li><li class=\"p-0 me-2\"><i class=\"fas fa-solid fa-calendar fa-fw\"><\/i> 2023<\/li><\/ul><div class=\"caption col-12 p-0 col-md-12 row m-0 align-items-center\"><div class=\"px-md-1\">    <h3 class=\"fw-medium m-0 small-space pt-2 pb-2 title-ss text-decoration-none border-bottom\">Dietary eicosapentaenoic acid and docosahexaenoic acid for mitochondrial biogenesis and dynamics<\/h3>\n\n    <div class=\"mt-0 row g-3\">\n        \n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-barcode fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>ISBN<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-file fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>P\u00e1ginas<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">D\u00e9sde la p\u00e1gina 213, hasta la p\u00e1gina 224<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-language fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Idioma<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-3 border-bottom pb-2\">\n            <small class=\"text-muted\">Ingl\u00e9s<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-newspaper fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editorial<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-5 border-bottom pb-2\">\n            <small class=\"text-muted\">Elsevier<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2 border-bottom pb-2\">\n            <small><i class=\"fas fa-solid fa-user-pen fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Editores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10 border-bottom pb-2\">\n            <small class=\"text-muted\"><\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-2\">\n            <small><i class=\"fas fa-solid fa-signature fa-fw me-2\" style=\"color: #8c9db3;\"><\/i>Autores<\/small>\n        <\/div>\n\n        <div class=\"col-12 col-sm-6 col-lg-10\">\n            <small class=\"text-muted\">Sebasti\u00e1n Jorge Jannas Vela, Mauricio Castro-Sepulveda<\/small>\n        <\/div>\n    <\/div><span class=\"caption-field-publish\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>[\/vc_tta_section][vc_tta_section title=&#8221;Contacto&#8221; tab_id=&#8221;contacto&#8221;][\/vc_tta_section][\/vc_tta_tabs][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"featured_media":87,"template":"","institute_academics":[3],"profile_academics":[7],"class_list":["post-86","academics","type-academics","status-publish","has-post-thumbnail","hentry","institute_academics-instituto-de-ciencias-de-la-salud","profile_academics-academico"],"rut_academico":"13832090-1","mail_academico":"sebastian.jannas@uoh.cl","n_proyectos":"9","n_publicaciones":"14","n_libros":"0","n_cap_libros":"1","n_otros_libros":"0","acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sebasti\u00e1n Jannas - Instituto de Ciencias de la Salud<\/title>\n<meta name=\"description\" content=\"Acad\u00e9mico del Instituto de Ciencias de la Salud de la Universidad Estatal de O&#039;Higgins.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sebasti\u00e1n Jannas - Instituto de Ciencias de la Salud\" \/>\n<meta property=\"og:description\" content=\"Acad\u00e9mico del Instituto de Ciencias de la Salud de la Universidad Estatal de O&#039;Higgins.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/academico\/sebastian-jannas\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto de Ciencias de la Salud\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T10:02:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-content\/uploads\/sites\/26\/2022\/04\/sebastian_jannas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/academico\/sebastian-jannas\/\",\"url\":\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/academico\/sebastian-jannas\/\",\"name\":\"Sebasti\u00e1n Jannas - Instituto de Ciencias de la Salud\",\"isPartOf\":{\"@id\":\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/academico\/sebastian-jannas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/academico\/sebastian-jannas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-content\/uploads\/sites\/26\/2022\/04\/sebastian_jannas.jpg\",\"datePublished\":\"2022-04-29T12:39:21+00:00\",\"dateModified\":\"2026-05-13T10:02:40+00:00\",\"description\":\"Acad\u00e9mico del Instituto de Ciencias de la Salud de la Universidad Estatal de O'Higgins.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/academico\/sebastian-jannas\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/academico\/sebastian-jannas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/academico\/sebastian-jannas\/#primaryimage\",\"url\":\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-content\/uploads\/sites\/26\/2022\/04\/sebastian_jannas.jpg\",\"contentUrl\":\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-content\/uploads\/sites\/26\/2022\/04\/sebastian_jannas.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/academico\/sebastian-jannas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Acad\u00e9micos\",\"item\":\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/academico\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sebasti\u00e1n Jannas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/#website\",\"url\":\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/\",\"name\":\"Instituto de Ciencias de la Salud\",\"description\":\"Otro sitio de Sitios de Universidad O'higgins\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sebasti\u00e1n Jannas - Instituto de Ciencias de la Salud","description":"Acad\u00e9mico del Instituto de Ciencias de la Salud de la Universidad Estatal de O'Higgins.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Sebasti\u00e1n Jannas - Instituto de Ciencias de la Salud","og_description":"Acad\u00e9mico del Instituto de Ciencias de la Salud de la Universidad Estatal de O'Higgins.","og_url":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/academico\/sebastian-jannas\/","og_site_name":"Instituto de Ciencias de la Salud","article_modified_time":"2026-05-13T10:02:40+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-content\/uploads\/sites\/26\/2022\/04\/sebastian_jannas.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/academico\/sebastian-jannas\/","url":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/academico\/sebastian-jannas\/","name":"Sebasti\u00e1n Jannas - Instituto de Ciencias de la Salud","isPartOf":{"@id":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/academico\/sebastian-jannas\/#primaryimage"},"image":{"@id":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/academico\/sebastian-jannas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-content\/uploads\/sites\/26\/2022\/04\/sebastian_jannas.jpg","datePublished":"2022-04-29T12:39:21+00:00","dateModified":"2026-05-13T10:02:40+00:00","description":"Acad\u00e9mico del Instituto de Ciencias de la Salud de la Universidad Estatal de O'Higgins.","breadcrumb":{"@id":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/academico\/sebastian-jannas\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/academico\/sebastian-jannas\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/academico\/sebastian-jannas\/#primaryimage","url":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-content\/uploads\/sites\/26\/2022\/04\/sebastian_jannas.jpg","contentUrl":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-content\/uploads\/sites\/26\/2022\/04\/sebastian_jannas.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/academico\/sebastian-jannas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Acad\u00e9micos","item":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/academico\/"},{"@type":"ListItem","position":2,"name":"Sebasti\u00e1n Jannas"}]},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/#website","url":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/","name":"Instituto de Ciencias de la Salud","description":"Otro sitio de Sitios de Universidad O'higgins","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-json\/wp\/v2\/academics\/86","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-json\/wp\/v2\/academics"}],"about":[{"href":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-json\/wp\/v2\/types\/academics"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-json\/wp\/v2\/media\/87"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-json\/wp\/v2\/media?parent=86"}],"wp:term":[{"taxonomy":"institute_academics","embeddable":true,"href":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-json\/wp\/v2\/institute_academics?post=86"},{"taxonomy":"profile_academics","embeddable":true,"href":"https:\/\/www.uoh.cl\/instituto-ciencias-de-la-salud\/wp-json\/wp\/v2\/profile_academics?post=86"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}