
{"id":11,"date":"2024-08-23T14:03:23","date_gmt":"2024-08-23T18:03:23","guid":{"rendered":"https:\/\/www.uoh.cl\/innovacion\/?page_id=11"},"modified":"2025-11-12T14:58:09","modified_gmt":"2025-11-12T18:58:09","slug":"transferencia-tecnologica","status":"publish","type":"page","link":"https:\/\/www.uoh.cl\/innovacion\/transferencia-tecnologica\/","title":{"rendered":"Transferencia Tecnol\u00f3gica"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]<div class=\"uoh_slider_featured_component component__featured-slide row mx-auto col-12 m-0 align-items-center position-relative lazyload\" style=\" background:inherit\" data-bg=\"url(https:\/\/www.uoh.cl\/innovacion\/wp-content\/uploads\/sites\/50\/2024\/08\/Foto_4_TRANSF-3.jpg)\"><div class=\"caption--degrade\"><svg  xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"1061px\" height=\"539px\"><defs><linearGradient id=\"PSgrad_0\" x1=\"0%\" x2=\"64.279%\" y1=\"76.604%\" y2=\"0%\"><stop offset=\"0%\" stop-color=\"rgb(66,160,248)\" stop-opacity=\"1\" \/><stop offset=\"100%\" stop-color=\"rgb(66,160,248)\" stop-opacity=\"0\" \/><\/linearGradient><\/defs><path fill-rule=\"evenodd\"  fill=\"none\" d=\"M311.000,515.000 C311.000,515.000 211.039,468.555 132.000,357.000 C21.864,201.555 -4.306,4.695 1.000,0.000 L196.000,0.000 L811.000,0.000 L1061.000,0.000 C1061.000,0.000 851.535,430.030 546.000,521.000 C402.674,563.674 311.000,515.000 311.000,515.000 Z\"\/> <path fill=\"url(#PSgrad_0)\"d=\"M311.000,515.000 C311.000,515.000 211.039,468.555 132.000,357.000 C21.864,201.555 -4.306,4.695 1.000,0.000 L196.000,0.000 L811.000,0.000 L1061.000,0.000 C1061.000,0.000 851.535,430.030 546.000,521.000 C402.674,563.674 311.000,515.000 311.000,515.000 Z\"\/><\/svg><\/div><div class=\"caption--quote\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"width=\"226px\" height=\"273px\"><defs><linearGradient id=\"PSgrad_0\" x1=\"71.934%\" x2=\"0%\" y1=\"69.466%\" y2=\"0%\"><stop offset=\"0%\" stop-color=\"rgb(66,160,248)\" stop-opacity=\"0.49\" \/><stop offset=\"100%\" stop-color=\"rgb(66,160,248)\" stop-opacity=\"0\" \/><\/linearGradient><\/defs><path fill-rule=\"evenodd\"  fill=\"none\" d=\"M-0.000,273.000 L174.000,273.000 C174.000,273.000 226.000,266.268 226.000,221.000 C226.000,175.732 226.000,-0.000 226.000,-0.000 C226.000,-0.000 24.577,71.878 -0.000,273.000 Z\"\/><path fill=\"url(#PSgrad_0)\"d=\"M-0.000,273.000 L174.000,273.000 C174.000,273.000 226.000,266.268 226.000,221.000 C226.000,175.732 226.000,-0.000 226.000,-0.000 C226.000,-0.000 24.577,71.878 -0.000,273.000 Z\"\/><\/svg><\/div><div class=\"my-uoh_slider_featured_component container mx-auto p-md-0\" ><div class=\"content component__featured-slide-content container row mx-auto aling-items-center p-0\"><h1 class=\"p-0 featured-slide title\"  style=\"\"><em>Direcci\u00f3n de Transferencia e Innovaci\u00f3n<\/em>Transferencia Tecnol\u00f3gica<\/h1><ul class=\"breadcrumb breadcrumb-list\"><li><a href=\"https:\/\/www.uoh.cl\/innovacion\">Inicio<\/a><\/li><li><span class=\"separator\"><?xml version=\"1.0\" ?><svg viewBox=\"0 0 96 96\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><title\/><path d=\"M39.3756,48.0022l30.47-25.39a6.0035,6.0035,0,0,0-7.6878-9.223L26.1563,43.3906a6.0092,6.0092,0,0,0,0,9.2231L62.1578,82.615a6.0035,6.0035,0,0,0,7.6878-9.2231Z\"\/><\/svg><\/span><\/li><li><a href=\"\"><\/a><\/li><li>Transferencia Tecnol\u00f3gica<\/li><\/ul><\/div><span><\/span><\/div><\/div>[\/vc_column][\/vc_row][vc_section el_class=&#8221;container mx-auto align-items-center circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row el_class=&#8221;pb-5&#8243;][vc_column][vc_wp_custommenu nav_menu=&#8221;4&#8243;]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/innovacion\"><span itemprop=\"name\">Direcci\u00f3n de Transferencia e Innovaci\u00f3n<\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Transferencia Tecnol\u00f3gica <\/span><meta itemprop=\"position\" content=\"3\" \/><\/ol><\/div>[\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;2\/3&#8243;]<div class=\"uoh_title_component-container\"><h2 class=\"title title--ms d-inline-block title--decorator  big-medium\">La Direcci\u00f3n de Transferencia e Innovaci\u00f3n desarrolla las siguientes actividades<\/h2><\/div>[\/vc_column][vc_column width=&#8221;1\/3&#8243;][\/vc_column][\/vc_row][\/vc_section][vc_section el_class=&#8221;p-md-0 pt-md-5&#8243; css=&#8221;.vc_custom_1724709127375{padding-bottom: 3rem !important;background-color: #f6faff !important;}&#8221;][vc_row el_class=&#8221;container mx-auto align-items-center p-md-0 pt-5&#8243;][vc_column el_class=&#8221;p-0&#8243;][vc_row_inner][vc_column_inner width=&#8221;1\/4&#8243;]<div class=\"box-container__info circle--pattern\" style=\"border-top: 4px solid #42a0f8\"><figure ><img decoding=\"async\" data-src=\"https:\/\/www.uoh.cl\/innovacion\/wp-content\/uploads\/sites\/50\/2024\/08\/apoyo.svg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><figcaption class=\"uoh_row m-0 align-items-center\">\n                        <div class=\"\"><h5 class=\"title__caption mb-3\"><\/h5><div> <p>Brindar apoyo y asesoramiento a acad\u00e9micos y emprendedores de la UOH para establecer estrategias de transferencia de resultados de investigaci\u00f3n.<\/p><\/div><\/div> <\/figcaption><\/figure><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;]<div class=\"box-container__info circle--pattern\" style=\"border-top: 4px solid #42a0f8\"><figure ><img decoding=\"async\" data-src=\"https:\/\/www.uoh.cl\/innovacion\/wp-content\/uploads\/sites\/50\/2024\/08\/scouting.svg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><figcaption class=\"uoh_row m-0 align-items-center\">\n                        <div class=\"\"><h5 class=\"title__caption mb-3\"><\/h5><div> <p>Realizar labores de scouting tecnol\u00f3gico.<\/p><\/div><\/div> <\/figcaption><\/figure><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;]<div class=\"box-container__info circle--pattern\" style=\"border-top: 4px solid #42a0f8\"><figure ><img decoding=\"async\" data-src=\"https:\/\/www.uoh.cl\/innovacion\/wp-content\/uploads\/sites\/50\/2024\/08\/portafolio.svg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><figcaption class=\"uoh_row m-0 align-items-center\">\n                        <div class=\"\"><h5 class=\"title__caption mb-3\"><\/h5><div> <p>Mantener actualizado el portafolio de tecnolog\u00edas.<\/p><\/div><\/div> <\/figcaption><\/figure><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;]<div class=\"box-container__info circle--pattern\" style=\"border-top: 4px solid #42a0f8\"><figure ><img decoding=\"async\" data-src=\"https:\/\/www.uoh.cl\/innovacion\/wp-content\/uploads\/sites\/50\/2024\/08\/alternativas.svg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><figcaption class=\"uoh_row m-0 align-items-center\">\n                        <div class=\"\"><h5 class=\"title__caption mb-3\"><\/h5><div> <p>Buscar alternativas de financiamiento para transformar los resultados de investigaci\u00f3n en aplicaciones pr\u00e1cticas y productos comercializables.<\/p><\/div><\/div> <\/figcaption><\/figure><\/div>[\/vc_column_inner][\/vc_row_inner][vc_zigzag color=&#8221;custom&#8221; custom_color=&#8221;#f6faff&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/4&#8243;]<div class=\"box-container__info circle--pattern\" style=\"border-top: 4px solid #42a0f8\"><figure ><img decoding=\"async\" data-src=\"https:\/\/www.uoh.cl\/innovacion\/wp-content\/uploads\/sites\/50\/2024\/08\/colaboraciones.svg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><figcaption class=\"uoh_row m-0 align-items-center\">\n                        <div class=\"\"><h5 class=\"title__caption mb-3\"><\/h5><div> <p>Establecer colaboraciones con la industria y otras instituciones.<\/p><\/div><\/div> <\/figcaption><\/figure><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;]<div class=\"box-container__info circle--pattern\" style=\"border-top: 4px solid #42a0f8\"><figure ><img decoding=\"async\" data-src=\"https:\/\/www.uoh.cl\/innovacion\/wp-content\/uploads\/sites\/50\/2024\/08\/estrategias.svg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><figcaption class=\"uoh_row m-0 align-items-center\">\n                        <div class=\"\"><h5 class=\"title__caption mb-3\"><\/h5><div> <p>Desarrollar estrategias de comercializaci\u00f3n.<\/p><\/div><\/div> <\/figcaption><\/figure><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;]<div class=\"box-container__info circle--pattern\" style=\"border-top: 4px solid #42a0f8\"><figure ><img decoding=\"async\" data-src=\"https:\/\/www.uoh.cl\/innovacion\/wp-content\/uploads\/sites\/50\/2024\/08\/financiacion.svg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><figcaption class=\"uoh_row m-0 align-items-center\">\n                        <div class=\"\"><h5 class=\"title__caption mb-3\"><\/h5><div> <p>Buscar financiaci\u00f3n y apoyar la creaci\u00f3n de emprendimientos de base tecnol\u00f3gica universitaria.<\/p><\/div><\/div> <\/figcaption><\/figure><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_section el_class=&#8221;p-md-0 pt-md-5 pb-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center&#8221;][vc_column width=&#8221;1\/2&#8243;]<div class=\"uoh_simple_image_component component__simple_image simple__image-left col-12\"><div class=\"uoh_simple_image_component\"><figure class=\"simple_image_contain\"><div> <img decoding=\"async\" data-src=\"https:\/\/www.uoh.cl\/innovacion\/wp-content\/uploads\/sites\/50\/2024\/08\/Foto_4_TRANSF-3.jpg\" class=\"w-100 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 900px; --smush-placeholder-aspect-ratio: 900\/527;\"> <\/div><\/figure><\/div><\/div>[\/vc_column][vc_column width=&#8221;1\/2&#8243;]<div class=\"uoh_title_component-container\"><h2 class=\"title title--ms d-inline-block title--decorator  medium\">Portafolio de Tecnolog\u00edas<\/h2><\/div>[vc_zigzag color=&#8221;custom&#8221; custom_color=&#8221;#FFFFFF&#8221;][vc_column_text css=&#8221;&#8221;]Aqu\u00ed podr\u00e1s encontrar las tecnolog\u00edas que se han creado en la Universidad de O\u2019Higgins. El prop\u00f3sito de esta secci\u00f3n es destacar las innovaciones con gran potencial para ser transferidas, con el objetivo de atraer a empresas o instituciones interesadas en comercializar o expandir los resultados de investigaci\u00f3n originados.[\/vc_column_text][vc_zigzag color=&#8221;custom&#8221; custom_color=&#8221;#FFFFFF&#8221;]<link rel=\"stylesheet\" id=\"font-awesome-css\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.5.1\/css\/all.min.css\" type=\"text\/css\" media=\"all\"><div class=\"show-files\"><div class=\"row g-5\"><div class=\"col-12 col-md-6 col-lg-12 mb-4\">\n    <div class=\"file-item h-100 position-relative\">\n        <a href=\"https:\/\/www.uoh.cl\/innovacion\/wp-content\/uploads\/sites\/50\/2025\/11\/Portafolio-de-Tecnologias.pdf\" target=\"_blank\">\n            <iframe class=\"file-image lazyload\" data-src=\"https:\/\/www.uoh.cl\/innovacion\/wp-content\/uploads\/sites\/50\/2025\/11\/Portafolio-de-Tecnologias.pdf#toolbar=0&navpanes=0\" width=\"100%\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-load-mode=\"1\"><\/iframe>\n        <\/a>\n        <h5 class=\"title--decorator my-3\">Portafolio de Tecnolog\u00edas<\/h5>\n        <div style=\"padding-bottom:50px\"><\/div>\n        <a style=\"bottom: 1.5rem; width: calc(100% - 3rem);\" class=\"only-download download-button-112 position-absolute\" href=\"https:\/\/www.uoh.cl\/innovacion\/wp-content\/uploads\/sites\/50\/2025\/11\/Portafolio-de-Tecnologias.pdf\" data-post-id=\"112\" target=\"_blank\"><i class=\"fa-solid fa-eye fa-fw\"><\/i>Ver<\/a>\n\n        <script src=\"https:\/\/code.jquery.com\/jquery-3.7.1.min.js\" integrity=\"sha256-\/JqT3SQfawRcv\/BIHPThkBvs0OEvtFFmqPF\/lYI\/Cxo=\" crossorigin=\"anonymous\"><\/script>\n\n        <script>\n        jQuery(document).ready(function($) {\n            $('.download-button-112').on('click', function(e) {\n                \/\/ var postId = $(this).data('post-id');\n                var postId = 112\n\n                $.ajax({\n                    url: '\/wp-admin\/admin-ajax.php',\n                        type: 'POST',\n                        data: {\n                            action: 'incrementar_contador_descargas',\n                            post_id: postId\n                        }\n                    });\n                });\n            });\n        <\/script>\n    <\/div>\n<\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row el_class=&#8221;container mx-auto align-items-center&#8221;][vc_column][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1724442955382{background-color: #edeff1 !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center p-md-0 pt-5&#8243;][vc_column el_class=&#8221;p-0&#8243;]<div class=\"uoh_title_component-container\"><h2 class=\"title title--ms d-inline-block title--decorator  big-medium\">Contacto<\/h2><\/div>[\/vc_column][\/vc_row][vc_row el_class=&#8221;container mx-auto align-items-center&#8221; css=&#8221;.vc_custom_1724444549824{padding-bottom: 3rem !important;}&#8221;][vc_column width=&#8221;1\/3&#8243;][vc_icon icon_fontawesome=&#8221;fab fa-linkedin&#8221; color=&#8221;custom&#8221; css=&#8221;&#8221; custom_color=&#8221;#2867b2&#8243;]<div class=\"uoh_link_component pe-4 d-inline-block py-1 simple inline\"><a href=\"https:\/\/www.linkedin.com\/in\/direcci\u00f3n-de-transferencia-e-innovaci\u00f3n-578b9831a\/?originalSubdomain=cl\"\n                                    class=\"link link--bold component__btn-content\"\n                                    title\"\"\n                                    target=\"_blank\"\n                                    rel=\"\">Direcci\u00f3n de Transferencia e Innovaci\u00f3n<span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div>[\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_icon icon_fontawesome=&#8221;fas fa-envelope&#8221; color=&#8221;custom&#8221; css=&#8221;&#8221; custom_color=&#8221;#2867b2&#8243;]<div class=\"uoh_link_component pe-4 d-inline-block py-1 simple inline\"><a href=\"mailto:direcci\u00f3n.transferencia@uoh.cl\"\n                                    class=\"link link--bold component__btn-content\"\n                                    title\"\"\n                                    target=\"_blank\"\n                                    rel=\"\">direcci\u00f3n.transferencia@uoh.cl<span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div>[\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;53&#8243; img_size=&#8221;240&#215;240&#8243; css=&#8221;&#8221;][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row][vc_section el_class=&#8221;container mx-auto align-items-center circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row el_class=&#8221;pb-5&#8243;][vc_column][vc_wp_custommenu nav_menu=&#8221;4&#8243;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;2\/3&#8243;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][\/vc_column][\/vc_row][\/vc_section][vc_section el_class=&#8221;p-md-0 pt-md-5&#8243; css=&#8221;.vc_custom_1724709127375{padding-bottom: 3rem !important;background-color: #f6faff !important;}&#8221;][vc_row el_class=&#8221;container mx-auto align-items-center p-md-0 pt-5&#8243;][vc_column el_class=&#8221;p-0&#8243;][vc_row_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][vc_zigzag color=&#8221;custom&#8221; custom_color=&#8221;#f6faff&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_section el_class=&#8221;p-md-0 pt-md-5 pb-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center&#8221;][vc_column width=&#8221;1\/2&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_zigzag color=&#8221;custom&#8221; custom_color=&#8221;#FFFFFF&#8221;][vc_column_text css=&#8221;&#8221;]Aqu\u00ed podr\u00e1s encontrar las tecnolog\u00edas que se han creado en [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-11","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferencia Tecnol\u00f3gica - Direcci\u00f3n de Transferencia e Innovaci\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uoh.cl\/innovacion\/transferencia-tecnologica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferencia Tecnol\u00f3gica - Direcci\u00f3n de Transferencia e Innovaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][\/vc_column][\/vc_row][vc_section el_class=&#8221;container mx-auto align-items-center circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row el_class=&#8221;pb-5&#8243;][vc_column][vc_wp_custommenu nav_menu=&#8221;4&#8243;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;2\/3&#8243;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][\/vc_column][\/vc_row][\/vc_section][vc_section el_class=&#8221;p-md-0 pt-md-5&#8243; css=&#8221;.vc_custom_1724709127375{padding-bottom: 3rem !important;background-color: #f6faff !important;}&#8221;][vc_row el_class=&#8221;container mx-auto align-items-center p-md-0 pt-5&#8243;][vc_column el_class=&#8221;p-0&#8243;][vc_row_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][vc_zigzag color=&#8221;custom&#8221; custom_color=&#8221;#f6faff&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_section el_class=&#8221;p-md-0 pt-md-5 pb-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center&#8221;][vc_column width=&#8221;1\/2&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_zigzag color=&#8221;custom&#8221; custom_color=&#8221;#FFFFFF&#8221;][vc_column_text css=&#8221;&#8221;]Aqu\u00ed podr\u00e1s encontrar las tecnolog\u00edas que se han creado en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/innovacion\/transferencia-tecnologica\/\" \/>\n<meta property=\"og:site_name\" content=\"Direcci\u00f3n de Transferencia e Innovaci\u00f3n\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-12T18:58:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uoh.cl\/innovacion\/transferencia-tecnologica\/\",\"url\":\"https:\/\/www.uoh.cl\/innovacion\/transferencia-tecnologica\/\",\"name\":\"Transferencia Tecnol\u00f3gica - Direcci\u00f3n de Transferencia e Innovaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.uoh.cl\/innovacion\/#website\"},\"datePublished\":\"2024-08-23T18:03:23+00:00\",\"dateModified\":\"2025-11-12T18:58:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.uoh.cl\/innovacion\/transferencia-tecnologica\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uoh.cl\/innovacion\/transferencia-tecnologica\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.uoh.cl\/innovacion\/transferencia-tecnologica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.uoh.cl\/innovacion\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferencia Tecnol\u00f3gica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uoh.cl\/innovacion\/#website\",\"url\":\"https:\/\/www.uoh.cl\/innovacion\/\",\"name\":\"Direcci\u00f3n de Transferencia e Innovaci\u00f3n\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.uoh.cl\/innovacion\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uoh.cl\/innovacion\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.uoh.cl\/innovacion\/#organization\",\"name\":\"Direcci\u00f3n de Transferencia e Innovaci\u00f3n\",\"url\":\"https:\/\/www.uoh.cl\/innovacion\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/innovacion\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.uoh.cl\/innovacion\/wp-content\/uploads\/sites\/50\/2024\/08\/Ddetei.svg\",\"contentUrl\":\"https:\/\/www.uoh.cl\/innovacion\/wp-content\/uploads\/sites\/50\/2024\/08\/Ddetei.svg\",\"caption\":\"Direcci\u00f3n de Transferencia e Innovaci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.uoh.cl\/innovacion\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Transferencia Tecnol\u00f3gica - Direcci\u00f3n de Transferencia e Innovaci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uoh.cl\/innovacion\/transferencia-tecnologica\/","og_locale":"es_ES","og_type":"article","og_title":"Transferencia Tecnol\u00f3gica - Direcci\u00f3n de Transferencia e Innovaci\u00f3n","og_description":"[vc_row][vc_column][\/vc_column][\/vc_row][vc_section el_class=&#8221;container mx-auto align-items-center circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row el_class=&#8221;pb-5&#8243;][vc_column][vc_wp_custommenu nav_menu=&#8221;4&#8243;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;2\/3&#8243;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][\/vc_column][\/vc_row][\/vc_section][vc_section el_class=&#8221;p-md-0 pt-md-5&#8243; css=&#8221;.vc_custom_1724709127375{padding-bottom: 3rem !important;background-color: #f6faff !important;}&#8221;][vc_row el_class=&#8221;container mx-auto align-items-center p-md-0 pt-5&#8243;][vc_column el_class=&#8221;p-0&#8243;][vc_row_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][vc_zigzag color=&#8221;custom&#8221; custom_color=&#8221;#f6faff&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_section el_class=&#8221;p-md-0 pt-md-5 pb-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center&#8221;][vc_column width=&#8221;1\/2&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_zigzag color=&#8221;custom&#8221; custom_color=&#8221;#FFFFFF&#8221;][vc_column_text css=&#8221;&#8221;]Aqu\u00ed podr\u00e1s encontrar las tecnolog\u00edas que se han creado en [&hellip;]","og_url":"https:\/\/www.uoh.cl\/innovacion\/transferencia-tecnologica\/","og_site_name":"Direcci\u00f3n de Transferencia e Innovaci\u00f3n","article_modified_time":"2025-11-12T18:58:09+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo estimado de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/innovacion\/transferencia-tecnologica\/","url":"https:\/\/www.uoh.cl\/innovacion\/transferencia-tecnologica\/","name":"Transferencia Tecnol\u00f3gica - Direcci\u00f3n de Transferencia e Innovaci\u00f3n","isPartOf":{"@id":"https:\/\/www.uoh.cl\/innovacion\/#website"},"datePublished":"2024-08-23T18:03:23+00:00","dateModified":"2025-11-12T18:58:09+00:00","breadcrumb":{"@id":"https:\/\/www.uoh.cl\/innovacion\/transferencia-tecnologica\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/innovacion\/transferencia-tecnologica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.uoh.cl\/innovacion\/transferencia-tecnologica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.uoh.cl\/innovacion\/"},{"@type":"ListItem","position":2,"name":"Transferencia Tecnol\u00f3gica"}]},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/innovacion\/#website","url":"https:\/\/www.uoh.cl\/innovacion\/","name":"Direcci\u00f3n de Transferencia e Innovaci\u00f3n","description":"","publisher":{"@id":"https:\/\/www.uoh.cl\/innovacion\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/innovacion\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/www.uoh.cl\/innovacion\/#organization","name":"Direcci\u00f3n de Transferencia e Innovaci\u00f3n","url":"https:\/\/www.uoh.cl\/innovacion\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/innovacion\/#\/schema\/logo\/image\/","url":"https:\/\/www.uoh.cl\/innovacion\/wp-content\/uploads\/sites\/50\/2024\/08\/Ddetei.svg","contentUrl":"https:\/\/www.uoh.cl\/innovacion\/wp-content\/uploads\/sites\/50\/2024\/08\/Ddetei.svg","caption":"Direcci\u00f3n de Transferencia e Innovaci\u00f3n"},"image":{"@id":"https:\/\/www.uoh.cl\/innovacion\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/innovacion\/wp-json\/wp\/v2\/pages\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/innovacion\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.uoh.cl\/innovacion\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/innovacion\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/innovacion\/wp-json\/wp\/v2\/comments?post=11"}],"version-history":[{"count":21,"href":"https:\/\/www.uoh.cl\/innovacion\/wp-json\/wp\/v2\/pages\/11\/revisions"}],"predecessor-version":[{"id":355,"href":"https:\/\/www.uoh.cl\/innovacion\/wp-json\/wp\/v2\/pages\/11\/revisions\/355"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/innovacion\/wp-json\/wp\/v2\/media?parent=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}