
{"id":2320,"date":"2024-05-16T13:04:10","date_gmt":"2024-05-16T16:04:10","guid":{"rendered":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/alerta-climatica-amenazas-para-las-abejas-y-la-cadena-alimentaria\/"},"modified":"2024-05-16T13:04:10","modified_gmt":"2024-05-16T16:04:10","slug":"alerta-climatica-amenazas-para-las-abejas-y-la-cadena-alimentaria","status":"publish","type":"post","link":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/alerta-climatica-amenazas-para-las-abejas-y-la-cadena-alimentaria\/","title":{"rendered":"Alerta clim\u00e1tica: amenazas para las abejas y la cadena alimentaria"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row][vc_column]<ul class=\"p-0 list-style-none d-inline-block\"><li class=\"p-0\"><a href=https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/category\/ica3\/ class=\"px-1 py-2\">ICA3<\/a><\/li><\/ul><div class=\"date_publish_post\"> \u25cf Jue 16 de Mayo 2024<\/div><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block title--decorator  big\">Alerta clim\u00e1tica: amenazas para las abejas y la cadena alimentaria<\/h1><\/div>[vc_row_inner el_class=&#8221;border-separator m-0&#8243;][vc_column_inner width=&#8221;2\/3&#8243;]<div class=\"author_wp_class\"> Escrito por <span>Universidad de O'Higgins<\/span><\/div>[\/vc_column_inner][vc_column_inner el_class=&#8221;align-items-end-publish&#8221; width=&#8221;1\/3&#8243;]<div class=\"uoh_social_network_component uoh_row col-12 justify-content-end m-0 p-0\"> <div class=\"icon__facebook-share-button\">\n                       <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/alerta-climatica-amenazas-para-las-abejas-y-la-cadena-alimentaria\/\" target=\"_blank\"> <div class=\"icon__facebook-svg\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22.4px\" height=\"48.3px\" viewBox=\"0 0 22.4 48.3\" style=\"overflow:visible;enable-background:new 0 0 22.4 48.3;\" xml:space=\"preserve\">\n                <defs>\n                <\/defs>\n                <path class=\"st0\" d=\"M22.4,15.6h-7.6v-5c0-1.9,1.2-2.3,2.1-2.3c0.9,0,5.4,0,5.4,0V0l-7.4,0C6.6,0,4.8,6.2,4.8,10.1v5.5H0v8.5h4.8\n                    c0,10.9,0,24.1,0,24.1h10c0,0,0-13.3,0-24.1h6.8L22.4,15.6z\"><\/path>\n                <\/svg><\/a><\/div>\n                    <\/div><div class=\"icon__twitter-share-button\">\n                        <div class=\"icon__twitter-svg\"><a target=\"_blank\" href=\"http:\/\/twitter.com\/share?url=https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/alerta-climatica-amenazas-para-las-abejas-y-la-cadena-alimentaria\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/a><\/div>\n                        <\/div><div class=\"icon__linkedin-share-button\">\n                        <div class=\"icon__linkedin-svg\">\n                        <a target=\"__blank\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/alerta-climatica-amenazas-para-las-abejas-y-la-cadena-alimentaria\/\"><svg enable-background=\"new 0 0 100 100\" height=\"100px\" id=\"Layer_1\" version=\"1.1\" viewBox=\"0 0 100 100\" width=\"100px\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><circle cx=\"50\" cy=\"50\" fill=\"#ccc\" r=\"45\"\/><g id=\"LinkedIn_1_\"><rect fill=\"#FFFFFF\" height=\"24.361\" width=\"7.69\" x=\"31.271\" y=\"43.569\"\/><path d=\"M59.968,43.334c-4.406,0-7.165,2.387-7.677,4.058v-3.823h-8.636c0.109,2.03,0,24.361,0,24.361h8.636    V54.748c0-0.733-0.034-1.465,0.19-1.991c0.594-1.464,1.869-2.985,4.162-2.985c2.998,0,4.361,2.253,4.361,5.552V67.93h8.721V54.384    C69.726,46.839,65.432,43.334,59.968,43.334z\" fill=\"#FFFFFF\"\/><path d=\"M34.973,32.069c-2.839,0-4.696,1.823-4.696,4.229c0,2.361,1.804,4.224,4.589,4.224h0.054    c2.891,0,4.69-1.869,4.69-4.229C39.555,33.888,37.81,32.069,34.973,32.069z\" fill=\"#FFFFFF\"\/><\/g><\/g><\/svg><\/a><\/div>\n\n            <\/div><\/div>[\/vc_column_inner][\/vc_row_inner]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\"><span itemprop=\"name\">Escuela de Ciencias Agroalimentarias, Animales y Ambientales.<\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Alerta clim\u00e1tica: amenazas para las abejas y la cadena alimentaria <\/span><meta itemprop=\"position\" content=\"3\" \/><\/ol><\/div>[vc_single_image image=&#8221;33848&#8243; img_size=&#8221;full&#8221; add_caption=&#8221;yes&#8221; alignment=&#8221;center&#8221; onclick=&#8221;img_link_large&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]\u00a0[\/vc_column_text][vc_column_text]<\/p>\n<ul>\n<li><i><span lang=\"es-419\">La acad\u00e9mica Andrea M\u00fcller explica que \u2013producto del cambio clim\u00e1tico- a las abejas les faltar\u00e1 alimento, lo que afectar\u00e1 directamente la producci\u00f3n de frutas, verduras y semillas.<\/span><\/i><\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_column_text]\u00a0[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"font-weight: 400\">Abejas, mariposas y polillas, junto a otros insectos y animales, realizan la esencial tarea de polinizar, permitiendo la producci\u00f3n de alimentos, esenciales para la vida humana y animal. De all\u00ed que preocupen los efectos que ocasiona el cambio clim\u00e1tico sobre los diferentes polinizadores.<\/p>\n<p style=\"font-weight: 400\"><a href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-agroalimentarias\/academico\/andrea-muller\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.uoh.cl\/instituto-de-ciencias-agroalimentarias\/academico\/andrea-muller\/&amp;source=gmail&amp;ust=1715956231373000&amp;usg=AOvVaw2p0ulQ5gnY07mz2cpGhiLe\">Andrea M\u00fcller<\/a>, acad\u00e9mica del\u00a0<a href=\"https:\/\/www.uoh.cl\/instituto-de-ciencias-agroalimentarias\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.uoh.cl\/instituto-de-ciencias-agroalimentarias\/&amp;source=gmail&amp;ust=1715956231373000&amp;usg=AOvVaw0joOOj1RgMnlCfxrocfX0r\">Instituto de Ciencias Agroalimentarias, Animales y Ambientales<\/a>\u00a0(ICA3) de la\u00a0<a href=\"http:\/\/www.uoh.cl\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.uoh.cl\/&amp;source=gmail&amp;ust=1715956231373000&amp;usg=AOvVaw2BTTXnWUhdeketJOyNswql\">Universidad de O\u2019Higgins<\/a>\u00a0(UOH) explica que el cambio clim\u00e1tico afecta a las abejas porque disminuye la disponibilidad de alimento que ellas requieren. \u201cLos cambios de temperatura extremos, muy altos o muy bajos, implican que la flora mel\u00edfera, que las abejas utilizan para alimentarse y producir miel, va disminuyendo de forma progresiva\u201d, a\u00f1ade. A esto se suma el aumento de los monocultivos o cultivos de una sola especie, lo cual disminuye la biodiversidad del \u00e1rea donde ellas pueden hacer pecoreo (lugar donde buscan n\u00e9ctar y polen) y, por ende, la variedad de nutrientes que requieren para alimentarse y tener una adecuada salud.<\/p>\n<h4 style=\"font-weight: 400\"><strong>Efectos sobre las personas<\/strong><\/h4>\n<p style=\"font-weight: 400\">\u201cSin suficiente alimento, los polinizadores y las abejas no pueden reproducirse de la misma forma; por lo tanto, tendremos menos polinizadores y menos acceso a frutas y verduras, ya que muchas de ellas -incluidas las semillas- necesitan de los polinizadores para producir el fruto\u201d, detalla la acad\u00e9mica.<\/p>\n<p style=\"font-weight: 400\">Sostiene que cuando hay menos polinizadores, \u201cexiste menor producci\u00f3n de frutas y de verduras y esto afecta la disponibilidad de alimentos necesarios para las personas y para los animales, afectando a la agricultura y a la seguridad alimentaria\u201d.<\/p>\n<h4 style=\"font-weight: 400\"><strong>\u00bfQu\u00e9 hacer para ayudar?<\/strong><\/h4>\n<p style=\"font-weight: 400\">Frente a este escenario, s\u00f3lo queda una forma de ayudar: \u201cresguardar que haya alimento para las abejas y los dem\u00e1s polinizadores\u201d, indica \u2013categ\u00f3rica- la acad\u00e9mica UOH Andrea M\u00fcller. Y se puede hacer de varias formas. \u201cEn \u00e9pocas de escasez de alimento, como en los meses de invierno, lo ideal es que las abejas se alimenten con su propia miel o si no suplementar de forma balanceada para que puedan sobrellevar este per\u00edodo\u201d.<\/p>\n<p style=\"font-weight: 400\">Agrega que es necesario implementar bordes florales o corredores biol\u00f3gicos para permitir el desarrollo de especies mel\u00edferas. \u201cEstos lugares en donde co-habitan diferentes flores, arbustos y \u00e1rboles permiten una biodiversidad que ayuda a disponer de alimento a las abejas y a todos los dem\u00e1s animales silvestres que viven en el lugar, ayudando a todos los polinizadores existentes en una zona determinada\u201d.<\/p>\n<p style=\"font-weight: 400\">Adem\u00e1s, sugiere que no se deben cortar o al menos no devastar las zonas de bosques nativos, que son las \u00e1reas donde las abejas y los polinizadores tambi\u00e9n obtienen su alimento.<\/p>\n<h4 style=\"font-weight: 400\"><strong>Proyectos en desarrollo<\/strong><\/h4>\n<p style=\"font-weight: 400\">El proyecto FIC &#8220;<strong><em>Programa de extensi\u00f3n e innovaci\u00f3n para la adaptaci\u00f3n de la apicultura al cambio clim\u00e1tico<\/em><\/strong>\u201d es liderado por la acad\u00e9mica UOH Andrea M\u00fcller. La iniciativa cuenta con el financiamiento del Gobierno Regional de O\u2019Higgins y busca, a trav\u00e9s de diferentes actividades, entregar herramientas que permitan a los apicultores adaptarse al cambio clim\u00e1tico.<\/p>\n<p style=\"font-weight: 400\">Los beneficiarios son apicultores de la Regi\u00f3n de O\u2019Higgins, junto a quienes trabajar\u00e1n para entregarles herramientas te\u00f3ricas -a trav\u00e9s de cursos y talleres- para adaptarse al nuevo escenario. Asimismo, les otorgar\u00e1n herramientas pr\u00e1cticas, gracias a la implementaci\u00f3n de unidades de mejoramiento productivo ap\u00edcola y un apiario demostrativo, explica la acad\u00e9mica.<\/p>\n<p style=\"font-weight: 400\">Tambi\u00e9n desarrollar\u00e1n un an\u00e1lisis territorial que permita fortalecer el sistema de trazabilidad de los productores ap\u00edcolas, y se continuar\u00e1 fortaleciendo el capital social, a trav\u00e9s de actividades de vinculaci\u00f3n con diferentes entidades nacionales y\/o internacionales.<\/p>\n<p style=\"font-weight: 400\">\u201cEl resultado final que buscamos es formar apicultores\/as y actores de la cadena ap\u00edcola, capacitados para desarrollar las diferentes actividades necesarias en la producci\u00f3n ap\u00edcola. Y que estas capacidades integradas al conocimiento les permitan realizar un manejo sostenible y resolver los problemas asociados al cambio clim\u00e1tico que enfrenten en el diario desempe\u00f1o de su profesi\u00f3n\u201d, se\u00f1ala la Dra. M\u00fcller.<\/p>\n<p style=\"font-weight: 400\">Las actividades se difundir\u00e1n y quedar\u00e1n disponibles en\u00a0<a href=\"http:\/\/www.apiuoh.cl\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.apiuoh.cl\/&amp;source=gmail&amp;ust=1715956231373000&amp;usg=AOvVaw28P-I8WSlFH1ydT9Aca0xw\">www.apiuoh.cl<\/a>\u00a0y en IG\u00a0<a href=\"https:\/\/www.instagram.com\/apiuoh\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.instagram.com\/apiuoh\/&amp;source=gmail&amp;ust=1715956231373000&amp;usg=AOvVaw3rX9ZUK5H9AZiyzaQ2XuJ0\">@apiuoh<\/a>.<\/p>\n<p>[\/vc_column_text][vc_zigzag color=&#8221;white&#8221;][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650255686594{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center p-md-0 pt-5 pb-5&#8243;][vc_column el_class=&#8221;pb-5&#8243;][vc_row_inner el_class=&#8221;pb-5&#8243;][vc_column_inner]<div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0\"><h2 class=\"title title--decorator title--ms d-inline-block\">Te Recomendamos<\/h2><\/div><\/div><div class=\"content-holder\"><div class=\"row  swipper-news-list not--activate-hack \"><div class=\"row -wrapper\"><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/category\/eca3\/\">\n                                        ECA3<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/wp-content\/uploads\/sites\/16\/2026\/05\/Giovanna-Amaya-Pena.png\" alt=\"Directora ECA3 es seleccionada como revisora del IPCC para informe clave sobre cambio clim\u00e1tico\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Lunes 11, Mayo<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/directora-eca3-es-seleccionada-como-revisora-del-ipcc-para-informe-clave-sobre-cambio-climatico\/\">\n                                    <h3 class=\"small-space\">Directora ECA3 es seleccionada como revisora del IPCC para informe clave sobre cambio clim\u00e1tico<\/h3><\/a>\n\n                                    <p>Giovanna Amaya participar\u00e1 en el cap\u00edtulo sobre proyecciones regionales y eventos extremos del S\u00e9ptimo Informe de Evaluaci\u00f3n del Panel Intergubernamental sobre Cambio Clim\u00e1tico.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/directora-eca3-es-seleccionada-como-revisora-del-ipcc-para-informe-clave-sobre-cambio-climatico\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/wp-content\/uploads\/sites\/16\/2026\/04\/Inauguracion-Ano-Academico-2026-6.jpg\" alt=\"Reflexi\u00f3n universitaria: UOH inaugura A\u00f1o Acad\u00e9mico 2026 pensando en los desaf\u00edos de la Educaci\u00f3n Superior\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Mi\u00e9rcoles 29, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/reflexion-universitaria-uoh-inaugura-ano-academico-2026-pensando-en-los-desafios-de-la-educacion-superior\/\">\n                                    <h3 class=\"small-space\">Reflexi\u00f3n universitaria: UOH inaugura A\u00f1o Acad\u00e9mico 2026 pensando en los desaf\u00edos de la Educaci\u00f3n Superior<\/h3><\/a>\n\n                                    <p>La ceremonia promovi\u00f3 el an\u00e1lisis acerca de los cambios educativos que se avecinan dentro de los procesos de formaci\u00f3n universitaria ajustados a contextos digitales.   <\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/reflexion-universitaria-uoh-inaugura-ano-academico-2026-pensando-en-los-desafios-de-la-educacion-superior\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/category\/investigacion\/\">\n                                        Investigaci\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/wp-content\/uploads\/sites\/16\/2026\/04\/SOLEDAD-BURRONE-EVALUANDO-1.jpg\" alt=\"Ciencia desde el aula: m\u00e1s de 40 proyectos se presentaron en el II Congreso de Investigaci\u00f3n de Estudiantes UOH\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Viernes 24, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/ciencia-desde-el-aula-mas-de-40-proyectos-se-presentaron-en-el-ii-congreso-de-investigacion-de-estudiantes-uoh\/\">\n                                    <h3 class=\"small-space\">Ciencia desde el aula: m\u00e1s de 40 proyectos se presentaron en el II Congreso de Investigaci\u00f3n de Estudiantes UOH<\/h3><\/a>\n\n                                    <p>La actividad reuni\u00f3 a estudiantes de pregrado y postgrado de las cinco escuelas e institutos de la Universidad de O\u2019Higgins, quienes expusieron sus trabajos en formato p\u00f3ster en diversas \u00e1reas del conocimiento.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/ciencia-desde-el-aula-mas-de-40-proyectos-se-presentaron-en-el-ii-congreso-de-investigacion-de-estudiantes-uoh\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pagination justify-content-center my-5\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/wp-json\/wp\/v2\/posts\/2320\/\/page\/2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/wp-json\/wp\/v2\/posts\/2320\/\/page\/3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/wp-json\/wp\/v2\/posts\/2320\/\/page\/147\">147<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/wp-json\/wp\/v2\/posts\/2320\/\/page\/2\"><div class=\"icon-pagination-next\"> <?xml version=\"1.0\" ?><svg viewBox=\"0 0 96 96\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><title\/><path d=\"M39.3756,48.0022l30.47-25.39a6.0035,6.0035,0,0,0-7.6878-9.223L26.1563,43.3906a6.0092,6.0092,0,0,0,0,9.2231L62.1578,82.615a6.0035,6.0035,0,0,0,7.6878-9.2231Z\"\/><\/svg> <\/div><\/a><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La acad\u00e9mica Andrea M\u00fcller explica que \u2013producto del cambio clim\u00e1tico- a las abejas les faltar\u00e1 alimento, lo que afectar\u00e1 directamente la producci\u00f3n de frutas, verduras y semillas.<\/p>\n","protected":false},"author":34,"featured_media":2321,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-2320","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ica3"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Alerta clim\u00e1tica: amenazas para las abejas y la cadena alimentaria - Escuela de Ciencias Agroalimentarias, Animales y Ambientales.<\/title>\n<meta name=\"description\" content=\"Juan Andr\u00e9s Pino ahond\u00f3 en las terapias ocupacionales comunitarias para el buen vivir.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alerta clim\u00e1tica: amenazas para las abejas y la cadena alimentaria - Escuela de Ciencias Agroalimentarias, Animales y Ambientales.\" \/>\n<meta property=\"og:description\" content=\"Juan Andr\u00e9s Pino ahond\u00f3 en las terapias ocupacionales comunitarias para el buen vivir.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/alerta-climatica-amenazas-para-las-abejas-y-la-cadena-alimentaria\/\" \/>\n<meta property=\"og:site_name\" content=\"Escuela de Ciencias Agroalimentarias, Animales y Ambientales.\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-16T16:04:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/wp-content\/uploads\/sites\/16\/2024\/05\/Abejas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Universidad de O&#039;Higgins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Universidad de O&#039;Higgins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/alerta-climatica-amenazas-para-las-abejas-y-la-cadena-alimentaria\/\",\"url\":\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/alerta-climatica-amenazas-para-las-abejas-y-la-cadena-alimentaria\/\",\"name\":\"Alerta clim\u00e1tica: amenazas para las abejas y la cadena alimentaria - Escuela de Ciencias Agroalimentarias, Animales y Ambientales.\",\"isPartOf\":{\"@id\":\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/alerta-climatica-amenazas-para-las-abejas-y-la-cadena-alimentaria\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/alerta-climatica-amenazas-para-las-abejas-y-la-cadena-alimentaria\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/wp-content\/uploads\/sites\/16\/2024\/05\/Abejas.jpg\",\"datePublished\":\"2024-05-16T16:04:10+00:00\",\"author\":{\"@id\":\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"description\":\"Juan Andr\u00e9s Pino ahond\u00f3 en las terapias ocupacionales comunitarias para el buen vivir.\",\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/alerta-climatica-amenazas-para-las-abejas-y-la-cadena-alimentaria\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/alerta-climatica-amenazas-para-las-abejas-y-la-cadena-alimentaria\/#primaryimage\",\"url\":\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/wp-content\/uploads\/sites\/16\/2024\/05\/Abejas.jpg\",\"contentUrl\":\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/wp-content\/uploads\/sites\/16\/2024\/05\/Abejas.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/#website\",\"url\":\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/\",\"name\":\"Escuela de Ciencias Agroalimentarias, Animales y Ambientales.\",\"description\":\"Otro sitio de Sitios de Universidad O'higgins\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\",\"name\":\"Universidad de O'Higgins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"caption\":\"Universidad de O'Higgins\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alerta clim\u00e1tica: amenazas para las abejas y la cadena alimentaria - Escuela de Ciencias Agroalimentarias, Animales y Ambientales.","description":"Juan Andr\u00e9s Pino ahond\u00f3 en las terapias ocupacionales comunitarias para el buen vivir.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Alerta clim\u00e1tica: amenazas para las abejas y la cadena alimentaria - Escuela de Ciencias Agroalimentarias, Animales y Ambientales.","og_description":"Juan Andr\u00e9s Pino ahond\u00f3 en las terapias ocupacionales comunitarias para el buen vivir.","og_url":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/alerta-climatica-amenazas-para-las-abejas-y-la-cadena-alimentaria\/","og_site_name":"Escuela de Ciencias Agroalimentarias, Animales y Ambientales.","article_published_time":"2024-05-16T16:04:10+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/wp-content\/uploads\/sites\/16\/2024\/05\/Abejas.jpg","type":"image\/jpeg"}],"author":"Universidad de O'Higgins","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Universidad de O'Higgins","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/alerta-climatica-amenazas-para-las-abejas-y-la-cadena-alimentaria\/","url":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/alerta-climatica-amenazas-para-las-abejas-y-la-cadena-alimentaria\/","name":"Alerta clim\u00e1tica: amenazas para las abejas y la cadena alimentaria - Escuela de Ciencias Agroalimentarias, Animales y Ambientales.","isPartOf":{"@id":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/alerta-climatica-amenazas-para-las-abejas-y-la-cadena-alimentaria\/#primaryimage"},"image":{"@id":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/alerta-climatica-amenazas-para-las-abejas-y-la-cadena-alimentaria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/wp-content\/uploads\/sites\/16\/2024\/05\/Abejas.jpg","datePublished":"2024-05-16T16:04:10+00:00","author":{"@id":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"description":"Juan Andr\u00e9s Pino ahond\u00f3 en las terapias ocupacionales comunitarias para el buen vivir.","inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/alerta-climatica-amenazas-para-las-abejas-y-la-cadena-alimentaria\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/alerta-climatica-amenazas-para-las-abejas-y-la-cadena-alimentaria\/#primaryimage","url":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/wp-content\/uploads\/sites\/16\/2024\/05\/Abejas.jpg","contentUrl":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/wp-content\/uploads\/sites\/16\/2024\/05\/Abejas.jpg","width":1000,"height":1000},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/#website","url":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/","name":"Escuela de Ciencias Agroalimentarias, Animales y Ambientales.","description":"Otro sitio de Sitios de Universidad O'higgins","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f","name":"Universidad de O'Higgins","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","caption":"Universidad de O'Higgins"}}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/wp-json\/wp\/v2\/posts\/2320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/wp-json\/wp\/v2\/comments?post=2320"}],"version-history":[{"count":0,"href":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/wp-json\/wp\/v2\/posts\/2320\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/wp-json\/wp\/v2\/media\/2321"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/wp-json\/wp\/v2\/media?parent=2320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/wp-json\/wp\/v2\/categories?post=2320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uoh.cl\/escuelas-de-ciencias-agroalimentarias\/wp-json\/wp\/v2\/tags?post=2320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}