
{"id":822,"date":"2022-10-28T09:43:51","date_gmt":"2022-10-27T12:43:51","guid":{"rendered":"https:\/\/www.uoh.cl\/escuela-de-salud\/2022\/10\/27\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\/"},"modified":"2022-10-27T12:37:24","modified_gmt":"2022-10-27T15:37:24","slug":"medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales","status":"publish","type":"post","link":"https:\/\/www.uoh.cl\/escuela-de-salud\/2022\/10\/28\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\/","title":{"rendered":"Medicina UOH: Con la misi\u00f3n de formar profesionales basado en las necesidades locales"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center text-right circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row][vc_column]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/escuela-de-salud\"><span itemprop=\"name\">Escuela de Salud<\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/noticias\/\"><span itemprop=\"name\">Noticias<\/span><\/a><meta itemprop=\"position\" content=\"3\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Medicina UOH: Con la misi\u00f3n de formar profesionales basado en <\/span><meta itemprop=\"position\" content=\"4\" \/><\/ol><\/div><ul class=\"p-0 list-style-none d-inline-block\"><li class=\"p-0\"><a href=https:\/\/www.uoh.cl\/escuela-de-salud\/category\/institucional\/ class=\"px-1 py-2\">Institucional<\/a><\/li><\/ul><div class=\"date_publish_post\"> \u25cf Vie 28 de Octubre 2022<\/div><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block title--decorator  big\">Medicina UOH: Con la misi\u00f3n de formar profesionales basado en las necesidades locales<\/h1><\/div>[vc_row_inner el_class=&#8221;border-separator m-0&#8243;][vc_column_inner width=&#8221;2\/3&#8243;][\/vc_column_inner][vc_column_inner el_class=&#8221;align-items-end-publish&#8221; width=&#8221;1\/3&#8243;]<div class=\"uoh_social_network_component uoh_row col-12 justify-content-end m-0 p-0\"> <div class=\"icon__facebook-share-button\">\n                       <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.uoh.cl\/escuela-de-salud\/2022\/10\/28\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\/\" target=\"_blank\"> <div class=\"icon__facebook-svg\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22.4px\" height=\"48.3px\" viewBox=\"0 0 22.4 48.3\" style=\"overflow:visible;enable-background:new 0 0 22.4 48.3;\" xml:space=\"preserve\">\n                <defs>\n                <\/defs>\n                <path class=\"st0\" d=\"M22.4,15.6h-7.6v-5c0-1.9,1.2-2.3,2.1-2.3c0.9,0,5.4,0,5.4,0V0l-7.4,0C6.6,0,4.8,6.2,4.8,10.1v5.5H0v8.5h4.8\n                    c0,10.9,0,24.1,0,24.1h10c0,0,0-13.3,0-24.1h6.8L22.4,15.6z\"><\/path>\n                <\/svg><\/a><\/div>\n                    <\/div><div class=\"icon__twitter-share-button\">\n                        <div class=\"icon__twitter-svg\"><a target=\"_blank\" href=\"http:\/\/twitter.com\/share?url=https:\/\/www.uoh.cl\/escuela-de-salud\/2022\/10\/28\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/a><\/div>\n                        <\/div><div class=\"icon__linkedin-share-button\">\n                        <div class=\"icon__linkedin-svg\">\n                        <a target=\"__blank\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.uoh.cl\/escuela-de-salud\/2022\/10\/28\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\/\"><svg enable-background=\"new 0 0 100 100\" height=\"100px\" id=\"Layer_1\" version=\"1.1\" viewBox=\"0 0 100 100\" width=\"100px\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><circle cx=\"50\" cy=\"50\" fill=\"#ccc\" r=\"45\"\/><g id=\"LinkedIn_1_\"><rect fill=\"#FFFFFF\" height=\"24.361\" width=\"7.69\" x=\"31.271\" y=\"43.569\"\/><path d=\"M59.968,43.334c-4.406,0-7.165,2.387-7.677,4.058v-3.823h-8.636c0.109,2.03,0,24.361,0,24.361h8.636    V54.748c0-0.733-0.034-1.465,0.19-1.991c0.594-1.464,1.869-2.985,4.162-2.985c2.998,0,4.361,2.253,4.361,5.552V67.93h8.721V54.384    C69.726,46.839,65.432,43.334,59.968,43.334z\" fill=\"#FFFFFF\"\/><path d=\"M34.973,32.069c-2.839,0-4.696,1.823-4.696,4.229c0,2.361,1.804,4.224,4.589,4.224h0.054    c2.891,0,4.69-1.869,4.69-4.229C39.555,33.888,37.81,32.069,34.973,32.069z\" fill=\"#FFFFFF\"\/><\/g><\/g><\/svg><\/a><\/div>\n\n            <\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_single_image image=&#8221;12036&#8243; img_size=&#8221;large&#8221;][vc_column_text]\u00a0[\/vc_column_text][vc_column_text]<em>La carrera ya cuenta con sus primeros\/as licenciados\/as, quienes realizan sus pr\u00e1cticas profesionales para la obtenci\u00f3n del t\u00edtulo.<\/em>[\/vc_column_text]<div class=\"author_wp_class\"> Escrito por <span>Universidad de O'Higgins<\/span><\/div>[vc_column_text]\u00a0[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"font-weight: 400\">La carrera de Medicina UOH brinda el conocimiento para diagnosticar y tratar pacientes, prevenir enfermedades, administrar los recursos farmacol\u00f3gicos y estar capacitado para los cambios cient\u00edficos y tecnol\u00f3gicos que exigen el mundo actual.<\/p>\n<p style=\"font-weight: 400\">Desde su primer a\u00f1o, la Universidad Estatal de O&#8217;Higgins (UOH) imparte la carrera de Medicina, que se desarrolla en base a asignaturas cient\u00edficas, humanistas y cl\u00ednicas, destac\u00e1ndose los aspectos \u00e9ticos, sociales y de pol\u00edticas de Salud P\u00fablica.<\/p>\n<p style=\"font-weight: 400\">El\/la estudiante, tras aprobar los primeros cinco a\u00f1os, obtiene el grado de Licenciado en Medicina, y luego de dos a\u00f1os de pr\u00e1ctica profesional, el t\u00edtulo de M\u00e9dico\/a Cirujano\/a.<\/p>\n<p style=\"font-weight: 400\">&#8220;Medicina UOH ha crecido en los \u00faltimos a\u00f1os y a pesar de no tener egresados, el avance fundamental ha estado en consolidar el equipo coordinador de la carrera y aumentar la dotaci\u00f3n de docentes adjuntos. En conjunto con lo anterior, se ha trabajado en aumentar los campos cl\u00ednicos\u00a0 de establecimientos p\u00fablicos y privados que juegan un rol importante en las pr\u00e1cticas de nuestros estudiantes en los distintos niveles de la carrera, por lo que esperamos fortalecer nuestra vinculaci\u00f3n con el medio en actividades de investigaci\u00f3n y capacitaci\u00f3n, por ejemplo, incorporando programas acad\u00e9micos de posgrado en aquellas especialidades falentes en la red asistencial regional&#8221;, apunta la jefa de carrera, Carmen Nadal.<\/p>\n<p style=\"font-weight: 400\">El egresado o egresada de Medicina UOH es un\/a profesional integral, con una formaci\u00f3n cient\u00edfica, humanista y \u00e9tica de calidad, que cuenta con habilidades para atender las necesidades de salud de las personas a lo largo de su ciclo vital. Diagnostica y elabora estrategias terap\u00e9uticas integrales, en estrecha relaci\u00f3n con el\/la paciente, su familia y la comunidad.<\/p>\n<p style=\"font-weight: 400\">&#8220;La formaci\u00f3n local de profesionales m\u00e9dicos para la Regi\u00f3n ha sido una deuda hist\u00f3rica. Si bien contamos con experiencias previas de otras universidades que se han establecido en los campos cl\u00ednicos de nuestra red asistencial, sus objetivos distan de una formaci\u00f3n con enfoque territorial, lo que genera una fuga de profesionales capacitados. La principal apuesta de la carrera de Medicina es formar profesionales para la regi\u00f3n basado en las necesidades locales&#8221;, asegur\u00f3 Carmen Nadal.<\/p>\n<p style=\"font-weight: 400\">Los\/as egresados\/as estar\u00e1n capacitados\/as para desarrollar estrategias de promoci\u00f3n y prevenci\u00f3n, as\u00ed como de gesti\u00f3n y de generaci\u00f3n de conocimiento, que contribuyen a mejorar las condiciones de salud de la poblaci\u00f3n. \u201cNuestro perfil de egreso se caracteriza por un profesional con formaci\u00f3n integral, compromiso social y enfoque regional. Esto permite una diversidad importante en el campo laboral de la regi\u00f3n principalmente fortaleciendo la atenci\u00f3n primaria, los hospitales de baja complejidad, la pr\u00e1ctica privada para el manejo de las patolog\u00edas de mayor prevalencia, la gesti\u00f3n en salud p\u00fablica y el desarrollo acad\u00e9mico en \u00e1reas de docencia\u201d, afirm\u00f3 la jefa de carrera.<\/p>\n<h3 style=\"font-weight: 400\"><strong>Campus Cl\u00ednico<\/strong><\/h3>\n<p>Durante el 2023, comenzar\u00e1 la construcci\u00f3n del primer Campus Cl\u00ednico al interior del Hospital Regional Libertador Bernardo O\u2019Higgins (HRLBO), con una edificaci\u00f3n en un terreno cercano a los 800 metros cuadrados. El centro contar\u00e1 con todo lo necesario como son las residencias, salas de simulaci\u00f3n, equipo tecnol\u00f3gico, salas de conferencia, biblioteca, entre otros espacios, para asegurar el desarrollo de conocimientos, habilidades y actitudes en la buena pr\u00e1ctica cl\u00ednica de los futuros profesionales.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650255686594{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center text-right p-md-0 pt-5 pb-5&#8243;][vc_column el_class=&#8221;pb-5&#8243;][vc_row_inner el_class=&#8221;pb-5&#8243;][vc_column_inner]<div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0\"><h2 class=\"title title--decorator title--ms d-inline-block\">Te Recomendamos<\/h2><\/div><\/div><div class=\"content-holder\"><div class=\"row  swipper-news-list not--activate-hack \"><div class=\"row -wrapper\"><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-content\/uploads\/sites\/19\/2026\/08\/Pukara-2.jpeg\" alt=\"Hist\u00f3rico acuerdo permitir\u00e1 a la UOH proteger y poner en valor el Pukar\u00e1 de La Compa\u00f1\u00eda\" style=\"--smush-placeholder-width: 1600px; --smush-placeholder-aspect-ratio: 1600\/1066;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Viernes 28, Agosto<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/2026\/08\/28\/historico-acuerdo-permitira-a-la-uoh-proteger-y-poner-en-valor-el-pukara-de-la-compania\/\">\n                                    <h3 class=\"small-space\">Hist\u00f3rico acuerdo permitir\u00e1 a la UOH proteger y poner en valor el Pukar\u00e1 de La Compa\u00f1\u00eda<\/h3><\/a>\n\n                                    <p>Acuerdo impulsado por el CDE permitir\u00e1 que uno de los sitios arqueol\u00f3gicos m\u00e1s importantes de Chile quede bajo el resguardo de una universidad estatal y se transforme en un espacio permanente para la investigaci\u00f3n cient\u00edfica, la educaci\u00f3n patrimonial y el desarrollo cultural de la Regi\u00f3n de O\u2019Higgins.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/2026\/08\/28\/historico-acuerdo-permitira-a-la-uoh-proteger-y-poner-en-valor-el-pukara-de-la-compania\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-content\/uploads\/sites\/19\/2026\/08\/Lanzamiento-App-TUI-UOH-25.jpg\" alt=\"UOH Campus Digital: Tu UOH, ahora en tu celular\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Jueves 27, Agosto<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/2026\/08\/27\/uoh-campus-digital-tu-uoh-ahora-en-tu-celular\/\">\n                                    <h3 class=\"small-space\">UOH Campus Digital: Tu UOH, ahora en tu celular<\/h3><\/a>\n\n                                    <p>La aplicaci\u00f3n m\u00f3vil reemplazar\u00e1 la antigua credencial TUI por una herramienta digital que permitir\u00e1 acceder a informaci\u00f3n universitaria, servicios y una amplia oferta de beneficios.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/2026\/08\/27\/uoh-campus-digital-tu-uoh-ahora-en-tu-celular\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-content\/uploads\/sites\/19\/2026\/08\/IMG_3001-scaled.jpg\" alt=\"UOH fortalece la incorporaci\u00f3n de nuevos docentes con jornada de inducci\u00f3n para el segundo semestre\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/1440;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Jueves 20, Agosto<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/2026\/08\/20\/uoh-fortalece-la-incorporacion-de-nuevos-docentes-con-jornada-de-induccion-para-el-segundo-semestre\/\">\n                                    <h3 class=\"small-space\">UOH fortalece la incorporaci\u00f3n de nuevos docentes con jornada de inducci\u00f3n para el segundo semestre<\/h3><\/a>\n\n                                    <p>La jornada reuni\u00f3 a m\u00e1s de 40 nuevas\/os docentes de las cinco escuelas de la Universidad de O\u2019Higgins, quienes conocieron aspectos institucionales y herramientas para fortalecer su labor.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/2026\/08\/20\/uoh-fortalece-la-incorporacion-de-nuevos-docentes-con-jornada-de-induccion-para-el-segundo-semestre\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pagination justify-content-center my-5\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/posts\/822\/\/page\/2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/posts\/822\/\/page\/3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/posts\/822\/\/page\/174\">174<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/posts\/822\/\/page\/2\"><div class=\"icon-pagination-next\"> <?xml version=\"1.0\" ?><svg viewBox=\"0 0 96 96\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><title\/><path d=\"M39.3756,48.0022l30.47-25.39a6.0035,6.0035,0,0,0-7.6878-9.223L26.1563,43.3906a6.0092,6.0092,0,0,0,0,9.2231L62.1578,82.615a6.0035,6.0035,0,0,0,7.6878-9.2231Z\"\/><\/svg> <\/div><\/a><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La carrera ya cuenta con sus primeros\/as licenciados\/as, quienes realizan sus pr\u00e1cticas profesionales para la obtenci\u00f3n del t\u00edtulo.<\/p>\n","protected":false},"author":34,"featured_media":830,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucional"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Medicina UOH: Con la misi\u00f3n de formar profesionales basado en las necesidades locales - Escuela de Salud<\/title>\n<meta name=\"description\" content=\"La carrera ya cuenta con sus primeros\/as licenciados\/as, quienes realizan sus pr\u00e1cticas profesionales para la obtenci\u00f3n del t\u00edtulo.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Medicina UOH: Con la misi\u00f3n de formar profesionales basado en las necesidades locales - Escuela de Salud\" \/>\n<meta property=\"og:description\" content=\"La carrera ya cuenta con sus primeros\/as licenciados\/as, quienes realizan sus pr\u00e1cticas profesionales para la obtenci\u00f3n del t\u00edtulo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/escuela-de-salud\/2022\/10\/27\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\/\" \/>\n<meta property=\"og:site_name\" content=\"Escuela de Salud\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-27T12:43:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-27T15:37:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-content\/uploads\/sites\/19\/2022\/10\/Medicina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Universidad de O&#039;Higgins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Universidad de O&#039;Higgins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-salud\\\/2022\\\/10\\\/27\\\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-salud\\\/2022\\\/10\\\/27\\\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\\\/\"},\"author\":{\"name\":\"Universidad de O'Higgins\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-salud\\\/#\\\/schema\\\/person\\\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"headline\":\"Medicina UOH: Con la misi\u00f3n de formar profesionales basado en las necesidades locales\",\"datePublished\":\"2022-10-27T12:43:51+00:00\",\"dateModified\":\"2022-10-27T15:37:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-salud\\\/2022\\\/10\\\/27\\\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\\\/\"},\"wordCount\":825,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-salud\\\/2022\\\/10\\\/27\\\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-salud\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2022\\\/10\\\/Medicina.jpg\",\"articleSection\":[\"Institucional\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-salud\\\/2022\\\/10\\\/27\\\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-salud\\\/2022\\\/10\\\/27\\\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\\\/\",\"url\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-salud\\\/2022\\\/10\\\/27\\\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\\\/\",\"name\":\"Medicina UOH: Con la misi\u00f3n de formar profesionales basado en las necesidades locales - Escuela de Salud\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-salud\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-salud\\\/2022\\\/10\\\/27\\\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-salud\\\/2022\\\/10\\\/27\\\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-salud\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2022\\\/10\\\/Medicina.jpg\",\"datePublished\":\"2022-10-27T12:43:51+00:00\",\"dateModified\":\"2022-10-27T15:37:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-salud\\\/#\\\/schema\\\/person\\\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"description\":\"La carrera ya cuenta con sus primeros\\\/as licenciados\\\/as, quienes realizan sus pr\u00e1cticas profesionales para la obtenci\u00f3n del t\u00edtulo.\",\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-salud\\\/2022\\\/10\\\/27\\\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-salud\\\/2022\\\/10\\\/27\\\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-salud\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2022\\\/10\\\/Medicina.jpg\",\"contentUrl\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-salud\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2022\\\/10\\\/Medicina.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-salud\\\/#website\",\"url\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-salud\\\/\",\"name\":\"Escuela de Salud\",\"description\":\"Otro sitio de Sitios de Universidad O'higgins\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-salud\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-salud\\\/#\\\/schema\\\/person\\\/ea242e676c7d6d7e46fc8b9e39486c4f\",\"name\":\"Universidad de O'Higgins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"caption\":\"Universidad de O'Higgins\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Medicina UOH: Con la misi\u00f3n de formar profesionales basado en las necesidades locales - Escuela de Salud","description":"La carrera ya cuenta con sus primeros\/as licenciados\/as, quienes realizan sus pr\u00e1cticas profesionales para la obtenci\u00f3n del t\u00edtulo.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Medicina UOH: Con la misi\u00f3n de formar profesionales basado en las necesidades locales - Escuela de Salud","og_description":"La carrera ya cuenta con sus primeros\/as licenciados\/as, quienes realizan sus pr\u00e1cticas profesionales para la obtenci\u00f3n del t\u00edtulo.","og_url":"https:\/\/www.uoh.cl\/escuela-de-salud\/2022\/10\/27\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\/","og_site_name":"Escuela de Salud","article_published_time":"2022-10-27T12:43:51+00:00","article_modified_time":"2022-10-27T15:37:24+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-content\/uploads\/sites\/19\/2022\/10\/Medicina.jpg","type":"image\/jpeg"}],"author":"Universidad de O'Higgins","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Universidad de O'Higgins","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/2022\/10\/27\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\/#article","isPartOf":{"@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/2022\/10\/27\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\/"},"author":{"name":"Universidad de O'Higgins","@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"headline":"Medicina UOH: Con la misi\u00f3n de formar profesionales basado en las necesidades locales","datePublished":"2022-10-27T12:43:51+00:00","dateModified":"2022-10-27T15:37:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/2022\/10\/27\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\/"},"wordCount":825,"commentCount":0,"image":{"@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/2022\/10\/27\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-content\/uploads\/sites\/19\/2022\/10\/Medicina.jpg","articleSection":["Institucional"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.uoh.cl\/escuela-de-salud\/2022\/10\/27\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/2022\/10\/27\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\/","url":"https:\/\/www.uoh.cl\/escuela-de-salud\/2022\/10\/27\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\/","name":"Medicina UOH: Con la misi\u00f3n de formar profesionales basado en las necesidades locales - Escuela de Salud","isPartOf":{"@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/2022\/10\/27\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\/#primaryimage"},"image":{"@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/2022\/10\/27\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-content\/uploads\/sites\/19\/2022\/10\/Medicina.jpg","datePublished":"2022-10-27T12:43:51+00:00","dateModified":"2022-10-27T15:37:24+00:00","author":{"@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"description":"La carrera ya cuenta con sus primeros\/as licenciados\/as, quienes realizan sus pr\u00e1cticas profesionales para la obtenci\u00f3n del t\u00edtulo.","inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/escuela-de-salud\/2022\/10\/27\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/2022\/10\/27\/medicina-uoh-con-la-mision-de-formar-profesionales-basado-en-las-necesidades-locales\/#primaryimage","url":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-content\/uploads\/sites\/19\/2022\/10\/Medicina.jpg","contentUrl":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-content\/uploads\/sites\/19\/2022\/10\/Medicina.jpg","width":1000,"height":1000},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/#website","url":"https:\/\/www.uoh.cl\/escuela-de-salud\/","name":"Escuela de Salud","description":"Otro sitio de Sitios de Universidad O'higgins","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/escuela-de-salud\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f","name":"Universidad de O'Higgins","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","caption":"Universidad de O'Higgins"}}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/posts\/822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/comments?post=822"}],"version-history":[{"count":1,"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/posts\/822\/revisions"}],"predecessor-version":[{"id":828,"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/posts\/822\/revisions\/828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/media\/830"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/media?parent=822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/categories?post=822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/tags?post=822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}