
{"id":2472,"date":"2024-03-28T09:21:29","date_gmt":"2024-03-28T12:21:29","guid":{"rendered":"https:\/\/www.uoh.cl\/escuela-de-salud\/2024\/03\/28\/cuanto-es-demasiado-nutricionista-uoh-aconseja-sobre-el-consumo-de-huevos-de-chocolate-en-pascua\/"},"modified":"2024-03-28T09:21:29","modified_gmt":"2024-03-28T12:21:29","slug":"cuanto-es-demasiado-nutricionista-uoh-aconseja-sobre-el-consumo-de-huevos-de-chocolate-en-pascua","status":"publish","type":"post","link":"https:\/\/www.uoh.cl\/escuela-de-salud\/2024\/03\/28\/cuanto-es-demasiado-nutricionista-uoh-aconseja-sobre-el-consumo-de-huevos-de-chocolate-en-pascua\/","title":{"rendered":"\u00bfCu\u00e1nto es demasiado? Nutricionista UOH aconseja sobre el consumo de huevos de chocolate en Pascua"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row][vc_column]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/escuela-de-salud\"><span itemprop=\"name\">Escuela de Salud<\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/noticias\/\"><span itemprop=\"name\">Noticias<\/span><\/a><meta itemprop=\"position\" content=\"3\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">\u00bfCu\u00e1nto es demasiado? Nutricionista UOH aconseja sobre el consumo de <\/span><meta itemprop=\"position\" content=\"4\" \/><\/ol><\/div><ul class=\"p-0 list-style-none d-inline-block\"><li class=\"p-0\"><a href=https:\/\/www.uoh.cl\/escuela-de-salud\/category\/salud\/ class=\"px-1 py-2\">Salud<\/a><\/li><\/ul><div class=\"date_publish_post\"> \u25cf Jue 28 de Marzo 2024<\/div><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block title--decorator  big\">\u00bfCu\u00e1nto es demasiado? Nutricionista UOH aconseja sobre el consumo de huevos de chocolate en Pascua<\/h1><\/div>[vc_row_inner el_class=&#8221;border-separator m-0&#8243;][vc_column_inner width=&#8221;2\/3&#8243;]<div class=\"author_wp_class\"> Escrito por <span>Universidad de O'Higgins<\/span><\/div>[\/vc_column_inner][vc_column_inner el_class=&#8221;align-items-end-publish&#8221; width=&#8221;1\/3&#8243;]<div class=\"uoh_social_network_component uoh_row col-12 justify-content-end m-0 p-0\"> <div class=\"icon__facebook-share-button\">\n                       <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.uoh.cl\/escuela-de-salud\/2024\/03\/28\/cuanto-es-demasiado-nutricionista-uoh-aconseja-sobre-el-consumo-de-huevos-de-chocolate-en-pascua\/\" target=\"_blank\"> <div class=\"icon__facebook-svg\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22.4px\" height=\"48.3px\" viewBox=\"0 0 22.4 48.3\" style=\"overflow:visible;enable-background:new 0 0 22.4 48.3;\" xml:space=\"preserve\">\n                <defs>\n                <\/defs>\n                <path class=\"st0\" d=\"M22.4,15.6h-7.6v-5c0-1.9,1.2-2.3,2.1-2.3c0.9,0,5.4,0,5.4,0V0l-7.4,0C6.6,0,4.8,6.2,4.8,10.1v5.5H0v8.5h4.8\n                    c0,10.9,0,24.1,0,24.1h10c0,0,0-13.3,0-24.1h6.8L22.4,15.6z\"><\/path>\n                <\/svg><\/a><\/div>\n                    <\/div><div class=\"icon__twitter-share-button\">\n                        <div class=\"icon__twitter-svg\"><a target=\"_blank\" href=\"http:\/\/twitter.com\/share?url=https:\/\/www.uoh.cl\/escuela-de-salud\/2024\/03\/28\/cuanto-es-demasiado-nutricionista-uoh-aconseja-sobre-el-consumo-de-huevos-de-chocolate-en-pascua\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/a><\/div>\n                        <\/div><div class=\"icon__linkedin-share-button\">\n                        <div class=\"icon__linkedin-svg\">\n                        <a target=\"__blank\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.uoh.cl\/escuela-de-salud\/2024\/03\/28\/cuanto-es-demasiado-nutricionista-uoh-aconseja-sobre-el-consumo-de-huevos-de-chocolate-en-pascua\/\"><svg enable-background=\"new 0 0 100 100\" height=\"100px\" id=\"Layer_1\" version=\"1.1\" viewBox=\"0 0 100 100\" width=\"100px\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><circle cx=\"50\" cy=\"50\" fill=\"#ccc\" r=\"45\"\/><g id=\"LinkedIn_1_\"><rect fill=\"#FFFFFF\" height=\"24.361\" width=\"7.69\" x=\"31.271\" y=\"43.569\"\/><path d=\"M59.968,43.334c-4.406,0-7.165,2.387-7.677,4.058v-3.823h-8.636c0.109,2.03,0,24.361,0,24.361h8.636    V54.748c0-0.733-0.034-1.465,0.19-1.991c0.594-1.464,1.869-2.985,4.162-2.985c2.998,0,4.361,2.253,4.361,5.552V67.93h8.721V54.384    C69.726,46.839,65.432,43.334,59.968,43.334z\" fill=\"#FFFFFF\"\/><path d=\"M34.973,32.069c-2.839,0-4.696,1.823-4.696,4.229c0,2.361,1.804,4.224,4.589,4.224h0.054    c2.891,0,4.69-1.869,4.69-4.229C39.555,33.888,37.81,32.069,34.973,32.069z\" fill=\"#FFFFFF\"\/><\/g><\/g><\/svg><\/a><\/div>\n\n            <\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_single_image image=&#8221;32138&#8243; img_size=&#8221;full&#8221; add_caption=&#8221;yes&#8221; alignment=&#8221;center&#8221; onclick=&#8221;img_link_large&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]\u00a0[\/vc_column_text][vc_column_text]<\/p>\n<ul>\n<li><i>La nutricionista Julia Pozo entreg\u00f3 sus recomendaciones para disfrutar de una Pascua saludable y equilibrada.<\/i><\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_column_text]\u00a0[\/vc_column_text][vc_column_text]El Domingo de Resurrecci\u00f3n es una fecha emblem\u00e1tica para disfrutar en familia y deleitarse con los cl\u00e1sicos huevos de chocolate. Sin embargo, es importante recordar que estos dulces, aunque deliciosos, pueden ser altos en az\u00facares y grasas, lo que nos lleva a preguntarnos: \u00bfcu\u00e1ntos huevos de chocolate podemos disfrutar sin excedernos?<\/p>\n<p>Los expertos en nutrici\u00f3n sugieren que, al igual que con cualquier otro alimento indulgente, la moderaci\u00f3n es fundamental. No hay una cantidad exacta recomendada, pero es importante tener en cuenta el tama\u00f1o y el contenido cal\u00f3rico de cada huevo de chocolate.<\/p>\n<p>En t\u00e9rminos generales, se sugiere que la ingesta de chocolate para ni\u00f1os oscile entre los 30 y 40 gramos diarios, lo que equivale aproximadamente a 5-6 unidades de huevitos peque\u00f1os. No obstante, esta cantidad puede variar seg\u00fan la edad del ni\u00f1o\/a y su nivel de actividad f\u00edsica.<\/p>\n<p>Julia Pozo, nutricionista y docente adjunta de la carrera de\u00a0<a href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/carreras\/nutricion-y-dietetica\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.uoh.cl\/escuela-de-salud\/carreras\/nutricion-y-dietetica\/&amp;source=gmail&amp;ust=1711713689415000&amp;usg=AOvVaw1Ln5Nr_KzoNw3_nnzbB6xA\">Nutrici\u00f3n y Diet\u00e9tica<\/a>\u00a0de la\u00a0<a href=\"http:\/\/www.uoh.cl\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.uoh.cl\/&amp;source=gmail&amp;ust=1711713689415000&amp;usg=AOvVaw02lsjfo7CT7_8d3vi0LBGJ\">Universidad de O\u2019Higgins<\/a>\u00a0(UOH), \u00a0indica que, para determinar la dosis adecuada de consumo de chocolate en ni\u00f1os, es imperativo \u201cconsiderar no solo su peso y edad, tambi\u00e9n su nivel de actividad f\u00edsica. Esto se debe a la necesidad de calcular su requerimiento energ\u00e9tico, lo que nos permitir\u00e1 establecer la cantidad de az\u00facar recomendada para cada individuo. Es importante tener en cuenta que los ni\u00f1os peque\u00f1os presentan un requerimiento energ\u00e9tico menor en comparaci\u00f3n con los adultos\u201d.<\/p>\n<p>\u201cPor ejemplo, un ni\u00f1o de 10 a\u00f1os requiere aproximadamente 1.880 kilo calor\u00edas diarias, lo que equivale a una recomendaci\u00f3n de consumo de az\u00facar de alrededor de 23 gramos por d\u00eda. Esta cifra se traduce en aproximadamente 5-6 unidades de huevitos peque\u00f1os de chocolate sin relleno. Estas pautas se basan en las recomendaciones de consumo de az\u00facar establecidas por la Organizaci\u00f3n Mundial de la Salud (OMS), as\u00ed como en el contenido de az\u00facar y otros nutrientes presentes en el chocolate\u201d, a\u00f1adi\u00f3.<\/p>\n<p>El exceso de consumo de chocolate puede ocasionar una serie de efectos adversos, incluyendo dolor abdominal, v\u00f3mitos y constipaci\u00f3n aguda. Adem\u00e1s, cabe destacar la alta densidad cal\u00f3rica y el contenido elevado de az\u00facar en el chocolate, factores que podr\u00edan incidir negativamente en la salud a largo plazo. \u00a0\u201cEs recomendable que los padres consideren establecer un racionamiento en la ingesta de dulces para sus hijos, distribuyendo su consumo a lo largo de varios d\u00edas, como medida preventiva para evitar un consumo excesivo\u201d, indic\u00f3 Julia Pozo.[\/vc_column_text][vc_zigzag color=&#8221;white&#8221;][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650255686594{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center p-md-0 pt-5 pb-5&#8243;][vc_column el_class=&#8221;pb-5&#8243;][vc_row_inner el_class=&#8221;pb-5&#8243;][vc_column_inner]<div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0\"><h2 class=\"title title--decorator title--ms d-inline-block\">Te Recomendamos<\/h2><\/div><\/div><div class=\"content-holder\"><div class=\"row  swipper-news-list not--activate-hack \"><div class=\"row -wrapper\"><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/category\/salud\/\">\n                                        Salud<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-content\/uploads\/sites\/19\/2026\/05\/MG_9665-scaled.jpg\" alt=\"Terapia Ocupacional UOH celebr\u00f3 investidura que marca el inicio de sus pr\u00e1cticas cl\u00ednicas\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/1734;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Viernes 8, Mayo<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/2026\/05\/08\/terapia-ocupacional-uoh-celebro-investidura-que-marca-el-inicio-de-sus-practicas-clinicas\/\">\n                                    <h3 class=\"small-space\">Terapia Ocupacional UOH celebr\u00f3 investidura que marca el inicio de sus pr\u00e1cticas cl\u00ednicas<\/h3><\/a>\n\n                                    <p>Las\/os estudiantes de tercer a\u00f1o recibieron por primera vez el uniforme cl\u00ednico que simboliza el compromiso \u00e9tico y profesional de la disciplina. <\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/2026\/05\/08\/terapia-ocupacional-uoh-celebro-investidura-que-marca-el-inicio-de-sus-practicas-clinicas\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/category\/salud\/\">\n                                        Salud<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-content\/uploads\/sites\/19\/2026\/05\/Estudiantes-de-Medicina-UOH-protagonizan-exitosa-Jornada-de-Salud-Mental-organizada-por-ASOMED-1.png\" alt=\"Estudiantes de Medicina UOH protagonizan exitosa Jornada de Salud Mental organizada por ASOMED\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Viernes 1, Mayo<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/2026\/05\/01\/estudiantes-de-medicina-uoh-protagonizan-exitosa-jornada-de-salud-mental-organizada-por-asomed\/\">\n                                    <h3 class=\"small-space\">Estudiantes de Medicina UOH protagonizan exitosa Jornada de Salud Mental organizada por ASOMED<\/h3><\/a>\n\n                                    <p>La actividad, realizada en el Campus Rancagua, reuni\u00f3 a estudiantes y docentes de la carrera, promoviendo el autocuidado, el bienestar emocional y el equilibrio en la formaci\u00f3n m\u00e9dica.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/2026\/05\/01\/estudiantes-de-medicina-uoh-protagonizan-exitosa-jornada-de-salud-mental-organizada-por-asomed\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-content\/uploads\/sites\/19\/2026\/04\/Inauguracion-Ano-Academico-2026-6.jpg\" alt=\"Reflexi\u00f3n universitaria: UOH inaugura A\u00f1o Acad\u00e9mico 2026 pensando en los desaf\u00edos de la Educaci\u00f3n Superior\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Mi\u00e9rcoles 29, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/2026\/04\/29\/reflexion-universitaria-uoh-inaugura-ano-academico-2026-pensando-en-los-desafios-de-la-educacion-superior\/\">\n                                    <h3 class=\"small-space\">Reflexi\u00f3n universitaria: UOH inaugura A\u00f1o Acad\u00e9mico 2026 pensando en los desaf\u00edos de la Educaci\u00f3n Superior<\/h3><\/a>\n\n                                    <p>La ceremonia promovi\u00f3 el an\u00e1lisis acerca de los cambios educativos que se avecinan dentro de los procesos de formaci\u00f3n universitaria ajustados a contextos digitales.   <\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/2026\/04\/29\/reflexion-universitaria-uoh-inaugura-ano-academico-2026-pensando-en-los-desafios-de-la-educacion-superior\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pagination justify-content-center my-5\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/posts\/2472\/\/page\/2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/posts\/2472\/\/page\/3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/posts\/2472\/\/page\/162\">162<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/posts\/2472\/\/page\/2\"><div class=\"icon-pagination-next\"> <?xml version=\"1.0\" ?><svg viewBox=\"0 0 96 96\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><title\/><path d=\"M39.3756,48.0022l30.47-25.39a6.0035,6.0035,0,0,0-7.6878-9.223L26.1563,43.3906a6.0092,6.0092,0,0,0,0,9.2231L62.1578,82.615a6.0035,6.0035,0,0,0,7.6878-9.2231Z\"\/><\/svg> <\/div><\/a><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La nutricionista Julia Pozo entreg\u00f3 sus recomendaciones para disfrutar de una Pascua saludable y equilibrada.<\/p>\n","protected":false},"author":34,"featured_media":2473,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[61],"tags":[],"class_list":["post-2472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfCu\u00e1nto es demasiado? Nutricionista UOH aconseja sobre el consumo de huevos de chocolate en Pascua - Escuela de Salud<\/title>\n<meta name=\"description\" content=\"Por segundo a\u00f1o consecutivo, Nestl\u00e9 Purina realiza el Happy Vet dirigido a las\/os estudiantes de la Escuela de Ciencias Agroalimentarias, Animales y Ambientales (ECA3).\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfCu\u00e1nto es demasiado? Nutricionista UOH aconseja sobre el consumo de huevos de chocolate en Pascua - Escuela de Salud\" \/>\n<meta property=\"og:description\" content=\"Por segundo a\u00f1o consecutivo, Nestl\u00e9 Purina realiza el Happy Vet dirigido a las\/os estudiantes de la Escuela de Ciencias Agroalimentarias, Animales y Ambientales (ECA3).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/escuela-de-salud\/2024\/03\/28\/cuanto-es-demasiado-nutricionista-uoh-aconseja-sobre-el-consumo-de-huevos-de-chocolate-en-pascua\/\" \/>\n<meta property=\"og:site_name\" content=\"Escuela de Salud\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-28T12:21:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-content\/uploads\/sites\/19\/2024\/03\/Huevos-de-chocolate.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Universidad de O&#039;Higgins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Universidad de O&#039;Higgins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-salud\/2024\/03\/28\/cuanto-es-demasiado-nutricionista-uoh-aconseja-sobre-el-consumo-de-huevos-de-chocolate-en-pascua\/\",\"url\":\"https:\/\/www.uoh.cl\/escuela-de-salud\/2024\/03\/28\/cuanto-es-demasiado-nutricionista-uoh-aconseja-sobre-el-consumo-de-huevos-de-chocolate-en-pascua\/\",\"name\":\"\u00bfCu\u00e1nto es demasiado? Nutricionista UOH aconseja sobre el consumo de huevos de chocolate en Pascua - Escuela de Salud\",\"isPartOf\":{\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-salud\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-salud\/2024\/03\/28\/cuanto-es-demasiado-nutricionista-uoh-aconseja-sobre-el-consumo-de-huevos-de-chocolate-en-pascua\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-salud\/2024\/03\/28\/cuanto-es-demasiado-nutricionista-uoh-aconseja-sobre-el-consumo-de-huevos-de-chocolate-en-pascua\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-content\/uploads\/sites\/19\/2024\/03\/Huevos-de-chocolate.jpg\",\"datePublished\":\"2024-03-28T12:21:29+00:00\",\"author\":{\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-salud\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"description\":\"Por segundo a\u00f1o consecutivo, Nestl\u00e9 Purina realiza el Happy Vet dirigido a las\/os estudiantes de la Escuela de Ciencias Agroalimentarias, Animales y Ambientales (ECA3).\",\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uoh.cl\/escuela-de-salud\/2024\/03\/28\/cuanto-es-demasiado-nutricionista-uoh-aconseja-sobre-el-consumo-de-huevos-de-chocolate-en-pascua\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-salud\/2024\/03\/28\/cuanto-es-demasiado-nutricionista-uoh-aconseja-sobre-el-consumo-de-huevos-de-chocolate-en-pascua\/#primaryimage\",\"url\":\"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-content\/uploads\/sites\/19\/2024\/03\/Huevos-de-chocolate.jpg\",\"contentUrl\":\"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-content\/uploads\/sites\/19\/2024\/03\/Huevos-de-chocolate.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-salud\/#website\",\"url\":\"https:\/\/www.uoh.cl\/escuela-de-salud\/\",\"name\":\"Escuela de Salud\",\"description\":\"Otro sitio de Sitios de Universidad O'higgins\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uoh.cl\/escuela-de-salud\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-salud\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\",\"name\":\"Universidad de O'Higgins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-salud\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"caption\":\"Universidad de O'Higgins\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfCu\u00e1nto es demasiado? Nutricionista UOH aconseja sobre el consumo de huevos de chocolate en Pascua - Escuela de Salud","description":"Por segundo a\u00f1o consecutivo, Nestl\u00e9 Purina realiza el Happy Vet dirigido a las\/os estudiantes de la Escuela de Ciencias Agroalimentarias, Animales y Ambientales (ECA3).","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"\u00bfCu\u00e1nto es demasiado? Nutricionista UOH aconseja sobre el consumo de huevos de chocolate en Pascua - Escuela de Salud","og_description":"Por segundo a\u00f1o consecutivo, Nestl\u00e9 Purina realiza el Happy Vet dirigido a las\/os estudiantes de la Escuela de Ciencias Agroalimentarias, Animales y Ambientales (ECA3).","og_url":"https:\/\/www.uoh.cl\/escuela-de-salud\/2024\/03\/28\/cuanto-es-demasiado-nutricionista-uoh-aconseja-sobre-el-consumo-de-huevos-de-chocolate-en-pascua\/","og_site_name":"Escuela de Salud","article_published_time":"2024-03-28T12:21:29+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-content\/uploads\/sites\/19\/2024\/03\/Huevos-de-chocolate.jpg","type":"image\/jpeg"}],"author":"Universidad de O'Higgins","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Universidad de O'Higgins","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/2024\/03\/28\/cuanto-es-demasiado-nutricionista-uoh-aconseja-sobre-el-consumo-de-huevos-de-chocolate-en-pascua\/","url":"https:\/\/www.uoh.cl\/escuela-de-salud\/2024\/03\/28\/cuanto-es-demasiado-nutricionista-uoh-aconseja-sobre-el-consumo-de-huevos-de-chocolate-en-pascua\/","name":"\u00bfCu\u00e1nto es demasiado? Nutricionista UOH aconseja sobre el consumo de huevos de chocolate en Pascua - Escuela de Salud","isPartOf":{"@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/2024\/03\/28\/cuanto-es-demasiado-nutricionista-uoh-aconseja-sobre-el-consumo-de-huevos-de-chocolate-en-pascua\/#primaryimage"},"image":{"@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/2024\/03\/28\/cuanto-es-demasiado-nutricionista-uoh-aconseja-sobre-el-consumo-de-huevos-de-chocolate-en-pascua\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-content\/uploads\/sites\/19\/2024\/03\/Huevos-de-chocolate.jpg","datePublished":"2024-03-28T12:21:29+00:00","author":{"@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"description":"Por segundo a\u00f1o consecutivo, Nestl\u00e9 Purina realiza el Happy Vet dirigido a las\/os estudiantes de la Escuela de Ciencias Agroalimentarias, Animales y Ambientales (ECA3).","inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/escuela-de-salud\/2024\/03\/28\/cuanto-es-demasiado-nutricionista-uoh-aconseja-sobre-el-consumo-de-huevos-de-chocolate-en-pascua\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/2024\/03\/28\/cuanto-es-demasiado-nutricionista-uoh-aconseja-sobre-el-consumo-de-huevos-de-chocolate-en-pascua\/#primaryimage","url":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-content\/uploads\/sites\/19\/2024\/03\/Huevos-de-chocolate.jpg","contentUrl":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-content\/uploads\/sites\/19\/2024\/03\/Huevos-de-chocolate.jpg","width":1000,"height":1000},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/#website","url":"https:\/\/www.uoh.cl\/escuela-de-salud\/","name":"Escuela de Salud","description":"Otro sitio de Sitios de Universidad O'higgins","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/escuela-de-salud\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f","name":"Universidad de O'Higgins","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","caption":"Universidad de O'Higgins"}}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/posts\/2472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/comments?post=2472"}],"version-history":[{"count":0,"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/posts\/2472\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/media\/2473"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/media?parent=2472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/categories?post=2472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/tags?post=2472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}