
{"id":1829,"date":"2023-05-22T10:25:06","date_gmt":"2023-05-22T13:25:06","guid":{"rendered":"https:\/\/www.uoh.cl\/escuela-de-salud\/2023\/05\/22\/vicerrectores-academicos-del-cruch-abordaron-desafios-sobre-diversidad-y-acompanamiento-en-las-universidades\/"},"modified":"2023-05-22T13:43:45","modified_gmt":"2023-05-22T16:43:45","slug":"vicerrectores-academicos-del-cruch-abordaron-desafios-sobre-diversidad-y-acompanamiento-en-las-universidades","status":"publish","type":"post","link":"https:\/\/www.uoh.cl\/escuela-de-salud\/2023\/05\/22\/vicerrectores-academicos-del-cruch-abordaron-desafios-sobre-diversidad-y-acompanamiento-en-las-universidades\/","title":{"rendered":"Vicerrectores Acad\u00e9micos del CRUCH abordaron desaf\u00edos sobre diversidad y acompa\u00f1amiento en las universidades"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row][vc_column]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/escuela-de-salud\"><span itemprop=\"name\">Escuela de Salud<\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/noticias\/\"><span itemprop=\"name\">Noticias<\/span><\/a><meta itemprop=\"position\" content=\"3\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Vicerrectores Acad\u00e9micos del CRUCH abordaron desaf\u00edos sobre diversidad y acompa\u00f1amiento <\/span><meta itemprop=\"position\" content=\"4\" \/><\/ol><\/div><ul class=\"p-0 list-style-none d-inline-block\"><li class=\"p-0\"><a href=https:\/\/www.uoh.cl\/escuela-de-salud\/category\/institucional\/ class=\"px-1 py-2\">Institucional<\/a><\/li><\/ul><div class=\"date_publish_post\"> \u25cf Lun 22 de Mayo 2023<\/div><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block title--decorator  big\">Vicerrectores Acad\u00e9micos del CRUCH abordaron desaf\u00edos sobre diversidad y acompa\u00f1amiento en las universidades<\/h1><\/div>[vc_row_inner el_class=&#8221;border-separator m-0&#8243;][vc_column_inner width=&#8221;2\/3&#8243;]<div class=\"author_wp_class\"> Escrito por <span>Universidad de O'Higgins<\/span><\/div>[\/vc_column_inner][vc_column_inner el_class=&#8221;align-items-end-publish&#8221; width=&#8221;1\/3&#8243;]<div class=\"uoh_social_network_component uoh_row col-12 justify-content-end m-0 p-0\"> <div class=\"icon__facebook-share-button\">\n                       <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.uoh.cl\/escuela-de-salud\/2023\/05\/22\/vicerrectores-academicos-del-cruch-abordaron-desafios-sobre-diversidad-y-acompanamiento-en-las-universidades\/\" target=\"_blank\"> <div class=\"icon__facebook-svg\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22.4px\" height=\"48.3px\" viewBox=\"0 0 22.4 48.3\" style=\"overflow:visible;enable-background:new 0 0 22.4 48.3;\" xml:space=\"preserve\">\n                <defs>\n                <\/defs>\n                <path class=\"st0\" d=\"M22.4,15.6h-7.6v-5c0-1.9,1.2-2.3,2.1-2.3c0.9,0,5.4,0,5.4,0V0l-7.4,0C6.6,0,4.8,6.2,4.8,10.1v5.5H0v8.5h4.8\n                    c0,10.9,0,24.1,0,24.1h10c0,0,0-13.3,0-24.1h6.8L22.4,15.6z\"><\/path>\n                <\/svg><\/a><\/div>\n                    <\/div><div class=\"icon__twitter-share-button\">\n                        <div class=\"icon__twitter-svg\"><a target=\"_blank\" href=\"http:\/\/twitter.com\/share?url=https:\/\/www.uoh.cl\/escuela-de-salud\/2023\/05\/22\/vicerrectores-academicos-del-cruch-abordaron-desafios-sobre-diversidad-y-acompanamiento-en-las-universidades\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/a><\/div>\n                        <\/div><div class=\"icon__linkedin-share-button\">\n                        <div class=\"icon__linkedin-svg\">\n                        <a target=\"__blank\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.uoh.cl\/escuela-de-salud\/2023\/05\/22\/vicerrectores-academicos-del-cruch-abordaron-desafios-sobre-diversidad-y-acompanamiento-en-las-universidades\/\"><svg enable-background=\"new 0 0 100 100\" height=\"100px\" id=\"Layer_1\" version=\"1.1\" viewBox=\"0 0 100 100\" width=\"100px\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><circle cx=\"50\" cy=\"50\" fill=\"#ccc\" r=\"45\"\/><g id=\"LinkedIn_1_\"><rect fill=\"#FFFFFF\" height=\"24.361\" width=\"7.69\" x=\"31.271\" y=\"43.569\"\/><path d=\"M59.968,43.334c-4.406,0-7.165,2.387-7.677,4.058v-3.823h-8.636c0.109,2.03,0,24.361,0,24.361h8.636    V54.748c0-0.733-0.034-1.465,0.19-1.991c0.594-1.464,1.869-2.985,4.162-2.985c2.998,0,4.361,2.253,4.361,5.552V67.93h8.721V54.384    C69.726,46.839,65.432,43.334,59.968,43.334z\" fill=\"#FFFFFF\"\/><path d=\"M34.973,32.069c-2.839,0-4.696,1.823-4.696,4.229c0,2.361,1.804,4.224,4.589,4.224h0.054    c2.891,0,4.69-1.869,4.69-4.229C39.555,33.888,37.81,32.069,34.973,32.069z\" fill=\"#FFFFFF\"\/><\/g><\/g><\/svg><\/a><\/div>\n\n            <\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_single_image image=&#8221;19103&#8243; img_size=&#8221;full&#8221; add_caption=&#8221;yes&#8221; alignment=&#8221;center&#8221; onclick=&#8221;img_link_large&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]\u00a0[\/vc_column_text][vc_column_text]<\/p>\n<ul>\n<li class=\"content__teaser\"><em>La reuni\u00f3n de la Comisi\u00f3n de Vicerrectores Acad\u00e9micos (CoVRA) y de la Red de Docencia de las Universidades del CRUCH cont\u00f3 con la participaci\u00f3n de la Rectora de la Universidad de Chile, Rosa Dev\u00e9s, de su par de la Universidad Alberto Hurtado, Eduardo Silva, y de quien preside la Comisi\u00f3n, David Figueroa Hern\u00e1ndez, vicerrector acad\u00e9mico de la Universidad Cat\u00f3lica de Temuco. Diversidad, inclusi\u00f3n y acompa\u00f1amiento fueron los temas que marcaron este encuentro.<\/em><\/li>\n<\/ul>\n<div class=\"content__related\">\n<div class=\"related__images\"><\/div>\n<\/div>\n<p>[\/vc_column_text][vc_column_text]\u00a0[\/vc_column_text][vc_column_text]En el sal\u00f3n Ignacio Domeyko se desarroll\u00f3 el encuentro de la\u00a0<strong>Comisi\u00f3n de Vicerrectores Acad\u00e9micos (CoVRA)<\/strong>\u00a0y\u00a0<strong>Red de Docencia de las Universidades del Consejo de Rectoras y Rectores de Universidades Chilenas<\/strong>, instancia que estuvo cruzada por el an\u00e1lisis sobre diversidad y acompa\u00f1amiento acad\u00e9mico en Educaci\u00f3n Superior. La actividad cont\u00f3 con la participaci\u00f3n de la Rectora de la Universidad de Chile,\u00a0<strong>Rosa Dev\u00e9s<\/strong>; de su par de la Universidad Alberto Hurtado,\u00a0<strong>Eduardo Silva<\/strong>; y de quien preside la Comisi\u00f3n que re\u00fane a las autoridades universitarias,\u00a0<strong>David Figueroa Hern\u00e1ndez<\/strong>, vicerrector Acad\u00e9mico de la Universidad Cat\u00f3lica de Temuco.<\/p>\n<p>La reuni\u00f3n fue inaugurada por la Rectora Dev\u00e9s, quien agradeci\u00f3 la asistencia de las y los presentes para reflexionar sobre los desaf\u00edos de sus cargos. \u201c<strong>El coraz\u00f3n de la universidad es lo acad\u00e9mico. Nuestra misi\u00f3n principal, que es la de formar, es una misi\u00f3n que est\u00e1 en nosotros mismos y que la hemos puesto en un lugar de transformaci\u00f3n<\/strong>, orientado por la l\u00f3gica de inclusi\u00f3n y por los desaf\u00edos que tiene nuestra sociedad, as\u00ed como tambi\u00e9n por lo que significa hoy d\u00eda formar para un mundo incierto, con el fin de entregar esos valores que todos reconocemos que son importantes, desde aquellos que nos permiten actuar con flexibilidad, como tambi\u00e9n la resiliencia. Sabemos que el mundo que viene es dif\u00edcil y que, por lo tanto, el sentido de comunidad, de apoyarnos unos a otros, es fundamental\u201d, dijo.<\/p>\n<p>Eduardo Silva, Rector de la Universidad Alberto Hurtado, plante\u00f3 que \u201c<strong>hay una sola cosa que no podemos dejar de hacer, que es el cultivo y la transmisi\u00f3n del saber<\/strong>. Ese cultivo se llama investigaci\u00f3n, ese cultivo se llama innovaci\u00f3n, generaci\u00f3n del conocimiento, implica la docencia, la ense\u00f1anza, el valor p\u00fablico (&#8230;) Ese es el coraz\u00f3n del asunto\u201d. Agreg\u00f3, adem\u00e1s, que \u201cen nuestras aulas y en nuestros laboratorios nuestros estudiantes, por lo pronto, son bastante distintos. Esta relaci\u00f3n de maestros y disc\u00edpulos se ha transformado y este car\u00e1cter superior parece que tiene que decirse de otra manera porque nuestras instituciones la verdad que antes eran para la \u00e9lite, una parte de la sociedad, que ten\u00eda acceso al saber superior. Se han hecho cargo de la masificaci\u00f3n, del acceso universal, de la formaci\u00f3n profesional, integral, a lo largo de toda la vida\u201d.<\/p>\n<p><strong>David Figueroa Hern\u00e1ndez<\/strong>, vicerrector Acad\u00e9mico de la Universidad Cat\u00f3lica de Temuco, plante\u00f3 que la instancia es \u201cun gran espacio de cooperaci\u00f3n, porque nos ayuda a ir resolviendo las problem\u00e1ticas que particularmente tenemos a veces en nuestras universidades. Y, obviamente, en estos espacios de cooperaci\u00f3n podemos cumplir con los prop\u00f3sitos que cada una de nuestras universidades tienen\u201d. En esta l\u00ednea, continu\u00f3, \u201csin duda, un foco central de todo el quehacer, de todas las personas que estamos aqu\u00ed, es precisamente la atenci\u00f3n a nuestros estudiantes. Ellos son el objeto de atenci\u00f3n, de servicio, de trabajo, en el cual muchas veces gastamos enormes cantidades de horas de trabajo, precisamente para<strong>\u00a0ir resolviendo las problem\u00e1ticas que estos j\u00f3venes tienen para que ellos puedan tener trayectorias acad\u00e9micas exitosas, que es un gran desaf\u00edo que todas las universidades hoy d\u00eda tenemos<\/strong>\u201d.<\/p>\n<p>Para dar inicio a la actividad, que se extendi\u00f3 por dos d\u00edas (jueves y viernes),\u00a0<strong>Pedro Milos<\/strong>, profesor de la Universidad Alberto Hurtado, expuso sobre\u00a0<strong>\u201cDesaf\u00edos de la Docencia Universitaria Post Pandemia\u201d<\/strong>. \u201cCuando hablamos de docencia universitaria, estamos hablando de algo tremendamente complejo, sometido a condicionantes muy diversas, en alg\u00fan sentido sistem\u00e1ticas, pero -al mismo tiempo- muy pr\u00e1cticas y cotidianas. Solo reconociendo la complejidad de la docencia universitaria podremos aquilatar las implicancias que tuvo un fen\u00f3meno en apariencia tan externo a la docencia universitaria como la pandemia\u201d, sostuvo el profesor Milos.<\/p>\n<p>En su exposici\u00f3n, abord\u00f3\u00a0<strong>los desaf\u00edos curriculares, la formaci\u00f3n integral, la formaci\u00f3n disciplinar, la salud mental, el uso intensivo de las tecnolog\u00edas y el desarrollo acad\u00e9mico y profesional del cuerpo docente<\/strong>. \u201cSi alguien me preguntara d\u00f3nde poner el foco en la docencia universitaria, teniendo en cuenta los elementos de contexto que ya dije y estas seis \u00e1reas espec\u00edficas en las cuales podr\u00edamos hacer cosas, yo dir\u00eda que\u00a0<strong>el foco es relevar la importancia del espacio microcurricular y de la sala de clases<\/strong>\u00a0(&#8230;) Durante la pandemia, la sala de clases fue el espacio m\u00e1s impactado en t\u00e9rminos de docencia universitaria, no fueron los planes de estudio. La sala de clase, con todo lo que ello implica y con la competencia nuestra como docentes, es lo que se vio m\u00e1s afectado\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Para cerrar las dos jornadas de trabajo, el vicerrector de Asuntos Acad\u00e9micos de la U. de Chile,\u00a0<strong>Claudio Pastenes<\/strong>, comparti\u00f3 algunas reflexiones. \u201cEl t\u00edtulo que nos convoc\u00f3 en esta oportunidad era\u00a0<strong>\u2018Diversidad, inclusi\u00f3n y acompa\u00f1amiento\u2019<\/strong>. Este t\u00edtulo existe porque nosotros creemos en la diversidad, y creemos en ella porque efectivamente genera un espacio donde distintas miradas, costumbres y culturas \u2013desde el punto de vista de las trayectorias educativas, de los pueblos originarios, del g\u00e9nero\u2013 interact\u00faan\u201d, expuso.<\/p>\n<p>\u201cEste fue un muy grato espacio de compartir muy honestamente estrategias, visiones y problemas, que nos hace muy bien.\u00a0<strong>Esta instancia tiene que romper con el paradigma de la competencia y, de hecho, creo que as\u00ed se dio.\u00a0<\/strong>Fue un momento, para m\u00ed, de mucha colaboraci\u00f3n, de mucha amistad, de mucho esp\u00edritu, de poner los problemas sobre la mesa, dejarlos ver y seguir conversando sobre ellos mismos\u201d, cerr\u00f3. Tambi\u00e9n destac\u00f3 la\u00a0<strong>importancia de ir incorporando conceptos como la neurodiversidad, la innovaci\u00f3n y el emprendimiento, y trabajar en la planificaci\u00f3n<\/strong>.<\/p>\n<p>En julio del a\u00f1o pasado, en Antofagasta, se reunieron la \u00faltima vez los vicerrectores y vicerrectoras acad\u00e9micas y la Red de Docencia de las Universidades del Consejo de Rectoras y Rectores. En 2021, tuvo lugar en la Universidad Alberto Hurtado, en 2020 no se realiz\u00f3 por la pandemia y en 2019 se hizo en la Universidad Arturo Prat.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650255686594{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center p-md-0 pt-5 pb-5&#8243;][vc_column el_class=&#8221;pb-5&#8243;][vc_row_inner el_class=&#8221;pb-5&#8243;][vc_column_inner]<div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0\"><h2 class=\"title title--decorator title--ms d-inline-block\">Te Recomendamos<\/h2><\/div><\/div><div class=\"content-holder\"><div class=\"row  swipper-news-list not--activate-hack \"><div class=\"row -wrapper\"><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/category\/salud\/\">\n                                        Salud<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-content\/uploads\/sites\/19\/2026\/05\/MG_9665-scaled.jpg\" alt=\"Terapia Ocupacional UOH celebr\u00f3 investidura que marca el inicio de sus pr\u00e1cticas cl\u00ednicas\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/1734;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Viernes 8, Mayo<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/2026\/05\/08\/terapia-ocupacional-uoh-celebro-investidura-que-marca-el-inicio-de-sus-practicas-clinicas\/\">\n                                    <h3 class=\"small-space\">Terapia Ocupacional UOH celebr\u00f3 investidura que marca el inicio de sus pr\u00e1cticas cl\u00ednicas<\/h3><\/a>\n\n                                    <p>Las\/os estudiantes de tercer a\u00f1o recibieron por primera vez el uniforme cl\u00ednico que simboliza el compromiso \u00e9tico y profesional de la disciplina. <\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/2026\/05\/08\/terapia-ocupacional-uoh-celebro-investidura-que-marca-el-inicio-de-sus-practicas-clinicas\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/category\/salud\/\">\n                                        Salud<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-content\/uploads\/sites\/19\/2026\/05\/Estudiantes-de-Medicina-UOH-protagonizan-exitosa-Jornada-de-Salud-Mental-organizada-por-ASOMED-1.png\" alt=\"Estudiantes de Medicina UOH protagonizan exitosa Jornada de Salud Mental organizada por ASOMED\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Viernes 1, Mayo<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/2026\/05\/01\/estudiantes-de-medicina-uoh-protagonizan-exitosa-jornada-de-salud-mental-organizada-por-asomed\/\">\n                                    <h3 class=\"small-space\">Estudiantes de Medicina UOH protagonizan exitosa Jornada de Salud Mental organizada por ASOMED<\/h3><\/a>\n\n                                    <p>La actividad, realizada en el Campus Rancagua, reuni\u00f3 a estudiantes y docentes de la carrera, promoviendo el autocuidado, el bienestar emocional y el equilibrio en la formaci\u00f3n m\u00e9dica.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/2026\/05\/01\/estudiantes-de-medicina-uoh-protagonizan-exitosa-jornada-de-salud-mental-organizada-por-asomed\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-content\/uploads\/sites\/19\/2026\/04\/Inauguracion-Ano-Academico-2026-6.jpg\" alt=\"Reflexi\u00f3n universitaria: UOH inaugura A\u00f1o Acad\u00e9mico 2026 pensando en los desaf\u00edos de la Educaci\u00f3n Superior\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Mi\u00e9rcoles 29, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/2026\/04\/29\/reflexion-universitaria-uoh-inaugura-ano-academico-2026-pensando-en-los-desafios-de-la-educacion-superior\/\">\n                                    <h3 class=\"small-space\">Reflexi\u00f3n universitaria: UOH inaugura A\u00f1o Acad\u00e9mico 2026 pensando en los desaf\u00edos de la Educaci\u00f3n Superior<\/h3><\/a>\n\n                                    <p>La ceremonia promovi\u00f3 el an\u00e1lisis acerca de los cambios educativos que se avecinan dentro de los procesos de formaci\u00f3n universitaria ajustados a contextos digitales.   <\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/2026\/04\/29\/reflexion-universitaria-uoh-inaugura-ano-academico-2026-pensando-en-los-desafios-de-la-educacion-superior\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pagination justify-content-center my-5\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/posts\/1829\/\/page\/2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/posts\/1829\/\/page\/3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/posts\/1829\/\/page\/162\">162<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/posts\/1829\/\/page\/2\"><div class=\"icon-pagination-next\"> <?xml version=\"1.0\" ?><svg viewBox=\"0 0 96 96\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><title\/><path d=\"M39.3756,48.0022l30.47-25.39a6.0035,6.0035,0,0,0-7.6878-9.223L26.1563,43.3906a6.0092,6.0092,0,0,0,0,9.2231L62.1578,82.615a6.0035,6.0035,0,0,0,7.6878-9.2231Z\"\/><\/svg> <\/div><\/a><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La reuni\u00f3n de la Comisi\u00f3n de Vicerrectores Acad\u00e9micos (CoVRA) y de la Red de Docencia de las Universidades del CRUCH cont\u00f3 con la participaci\u00f3n de la Rectora de la Universidad de Chile, Rosa Dev\u00e9s, de su par de la Universidad Alberto Hurtado, Eduardo Silva, y de quien preside la Comisi\u00f3n, David Figueroa Hern\u00e1ndez, vicerrector acad\u00e9mico de la Universidad Cat\u00f3lica de Temuco. Diversidad, inclusi\u00f3n y acompa\u00f1amiento fueron los temas que marcaron este encuentro.<\/p>\n","protected":false},"author":34,"featured_media":19104,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1829","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucional"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vicerrectores Acad\u00e9micos del CRUCH abordaron desaf\u00edos sobre diversidad y acompa\u00f1amiento en las universidades - Escuela de Salud<\/title>\n<meta name=\"description\" content=\"La reuni\u00f3n de la Comisi\u00f3n de Vicerrectores Acad\u00e9micos (CoVRA) y de la Red de Docencia de las Universidades del CRUCH cont\u00f3 con la participaci\u00f3n de la Rectora de la Universidad de Chile, Rosa Dev\u00e9s, de su par de la Universidad Alberto Hurtado, Eduardo Silva, y de quien preside la Comisi\u00f3n, David Figueroa Hern\u00e1ndez, vicerrector acad\u00e9mico de la Universidad Cat\u00f3lica de Temuco. Diversidad, inclusi\u00f3n y acompa\u00f1amiento fueron los temas que marcaron este encuentro.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vicerrectores Acad\u00e9micos del CRUCH abordaron desaf\u00edos sobre diversidad y acompa\u00f1amiento en las universidades - Escuela de Salud\" \/>\n<meta property=\"og:description\" content=\"La reuni\u00f3n de la Comisi\u00f3n de Vicerrectores Acad\u00e9micos (CoVRA) y de la Red de Docencia de las Universidades del CRUCH cont\u00f3 con la participaci\u00f3n de la Rectora de la Universidad de Chile, Rosa Dev\u00e9s, de su par de la Universidad Alberto Hurtado, Eduardo Silva, y de quien preside la Comisi\u00f3n, David Figueroa Hern\u00e1ndez, vicerrector acad\u00e9mico de la Universidad Cat\u00f3lica de Temuco. Diversidad, inclusi\u00f3n y acompa\u00f1amiento fueron los temas que marcaron este encuentro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/escuela-de-salud\/2023\/05\/22\/vicerrectores-academicos-del-cruch-abordaron-desafios-sobre-diversidad-y-acompanamiento-en-las-universidades\/\" \/>\n<meta property=\"og:site_name\" content=\"Escuela de Salud\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-22T13:25:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-22T16:43:45+00:00\" \/>\n<meta name=\"author\" content=\"Universidad de O&#039;Higgins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Universidad de O&#039;Higgins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-salud\/2023\/05\/22\/vicerrectores-academicos-del-cruch-abordaron-desafios-sobre-diversidad-y-acompanamiento-en-las-universidades\/\",\"url\":\"https:\/\/www.uoh.cl\/escuela-de-salud\/2023\/05\/22\/vicerrectores-academicos-del-cruch-abordaron-desafios-sobre-diversidad-y-acompanamiento-en-las-universidades\/\",\"name\":\"Vicerrectores Acad\u00e9micos del CRUCH abordaron desaf\u00edos sobre diversidad y acompa\u00f1amiento en las universidades - Escuela de Salud\",\"isPartOf\":{\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-salud\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-salud\/2023\/05\/22\/vicerrectores-academicos-del-cruch-abordaron-desafios-sobre-diversidad-y-acompanamiento-en-las-universidades\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-salud\/2023\/05\/22\/vicerrectores-academicos-del-cruch-abordaron-desafios-sobre-diversidad-y-acompanamiento-en-las-universidades\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2023-05-22T13:25:06+00:00\",\"dateModified\":\"2023-05-22T16:43:45+00:00\",\"author\":{\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-salud\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"description\":\"La reuni\u00f3n de la Comisi\u00f3n de Vicerrectores Acad\u00e9micos (CoVRA) y de la Red de Docencia de las Universidades del CRUCH cont\u00f3 con la participaci\u00f3n de la Rectora de la Universidad de Chile, Rosa Dev\u00e9s, de su par de la Universidad Alberto Hurtado, Eduardo Silva, y de quien preside la Comisi\u00f3n, David Figueroa Hern\u00e1ndez, vicerrector acad\u00e9mico de la Universidad Cat\u00f3lica de Temuco. Diversidad, inclusi\u00f3n y acompa\u00f1amiento fueron los temas que marcaron este encuentro.\",\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uoh.cl\/escuela-de-salud\/2023\/05\/22\/vicerrectores-academicos-del-cruch-abordaron-desafios-sobre-diversidad-y-acompanamiento-en-las-universidades\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-salud\/2023\/05\/22\/vicerrectores-academicos-del-cruch-abordaron-desafios-sobre-diversidad-y-acompanamiento-en-las-universidades\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-salud\/#website\",\"url\":\"https:\/\/www.uoh.cl\/escuela-de-salud\/\",\"name\":\"Escuela de Salud\",\"description\":\"Otro sitio de Sitios de Universidad O'higgins\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uoh.cl\/escuela-de-salud\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-salud\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\",\"name\":\"Universidad de O'Higgins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-salud\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"caption\":\"Universidad de O'Higgins\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vicerrectores Acad\u00e9micos del CRUCH abordaron desaf\u00edos sobre diversidad y acompa\u00f1amiento en las universidades - Escuela de Salud","description":"La reuni\u00f3n de la Comisi\u00f3n de Vicerrectores Acad\u00e9micos (CoVRA) y de la Red de Docencia de las Universidades del CRUCH cont\u00f3 con la participaci\u00f3n de la Rectora de la Universidad de Chile, Rosa Dev\u00e9s, de su par de la Universidad Alberto Hurtado, Eduardo Silva, y de quien preside la Comisi\u00f3n, David Figueroa Hern\u00e1ndez, vicerrector acad\u00e9mico de la Universidad Cat\u00f3lica de Temuco. Diversidad, inclusi\u00f3n y acompa\u00f1amiento fueron los temas que marcaron este encuentro.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Vicerrectores Acad\u00e9micos del CRUCH abordaron desaf\u00edos sobre diversidad y acompa\u00f1amiento en las universidades - Escuela de Salud","og_description":"La reuni\u00f3n de la Comisi\u00f3n de Vicerrectores Acad\u00e9micos (CoVRA) y de la Red de Docencia de las Universidades del CRUCH cont\u00f3 con la participaci\u00f3n de la Rectora de la Universidad de Chile, Rosa Dev\u00e9s, de su par de la Universidad Alberto Hurtado, Eduardo Silva, y de quien preside la Comisi\u00f3n, David Figueroa Hern\u00e1ndez, vicerrector acad\u00e9mico de la Universidad Cat\u00f3lica de Temuco. Diversidad, inclusi\u00f3n y acompa\u00f1amiento fueron los temas que marcaron este encuentro.","og_url":"https:\/\/www.uoh.cl\/escuela-de-salud\/2023\/05\/22\/vicerrectores-academicos-del-cruch-abordaron-desafios-sobre-diversidad-y-acompanamiento-en-las-universidades\/","og_site_name":"Escuela de Salud","article_published_time":"2023-05-22T13:25:06+00:00","article_modified_time":"2023-05-22T16:43:45+00:00","author":"Universidad de O'Higgins","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Universidad de O'Higgins","Tiempo estimado de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/2023\/05\/22\/vicerrectores-academicos-del-cruch-abordaron-desafios-sobre-diversidad-y-acompanamiento-en-las-universidades\/","url":"https:\/\/www.uoh.cl\/escuela-de-salud\/2023\/05\/22\/vicerrectores-academicos-del-cruch-abordaron-desafios-sobre-diversidad-y-acompanamiento-en-las-universidades\/","name":"Vicerrectores Acad\u00e9micos del CRUCH abordaron desaf\u00edos sobre diversidad y acompa\u00f1amiento en las universidades - Escuela de Salud","isPartOf":{"@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/2023\/05\/22\/vicerrectores-academicos-del-cruch-abordaron-desafios-sobre-diversidad-y-acompanamiento-en-las-universidades\/#primaryimage"},"image":{"@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/2023\/05\/22\/vicerrectores-academicos-del-cruch-abordaron-desafios-sobre-diversidad-y-acompanamiento-en-las-universidades\/#primaryimage"},"thumbnailUrl":"","datePublished":"2023-05-22T13:25:06+00:00","dateModified":"2023-05-22T16:43:45+00:00","author":{"@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"description":"La reuni\u00f3n de la Comisi\u00f3n de Vicerrectores Acad\u00e9micos (CoVRA) y de la Red de Docencia de las Universidades del CRUCH cont\u00f3 con la participaci\u00f3n de la Rectora de la Universidad de Chile, Rosa Dev\u00e9s, de su par de la Universidad Alberto Hurtado, Eduardo Silva, y de quien preside la Comisi\u00f3n, David Figueroa Hern\u00e1ndez, vicerrector acad\u00e9mico de la Universidad Cat\u00f3lica de Temuco. Diversidad, inclusi\u00f3n y acompa\u00f1amiento fueron los temas que marcaron este encuentro.","inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/escuela-de-salud\/2023\/05\/22\/vicerrectores-academicos-del-cruch-abordaron-desafios-sobre-diversidad-y-acompanamiento-en-las-universidades\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/2023\/05\/22\/vicerrectores-academicos-del-cruch-abordaron-desafios-sobre-diversidad-y-acompanamiento-en-las-universidades\/#primaryimage","url":"","contentUrl":""},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/#website","url":"https:\/\/www.uoh.cl\/escuela-de-salud\/","name":"Escuela de Salud","description":"Otro sitio de Sitios de Universidad O'higgins","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/escuela-de-salud\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f","name":"Universidad de O'Higgins","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/escuela-de-salud\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","caption":"Universidad de O'Higgins"}}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/posts\/1829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/comments?post=1829"}],"version-history":[{"count":1,"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/posts\/1829\/revisions"}],"predecessor-version":[{"id":1831,"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/posts\/1829\/revisions\/1831"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/media?parent=1829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/categories?post=1829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-salud\/wp-json\/wp\/v2\/tags?post=1829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}