
{"id":1929,"date":"2024-03-25T15:59:13","date_gmt":"2024-03-25T18:59:13","guid":{"rendered":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/2024\/03\/25\/declaracion-publica-cruch\/"},"modified":"2024-03-26T09:08:39","modified_gmt":"2024-03-26T12:08:39","slug":"declaracion-publica-cruch","status":"publish","type":"post","link":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/2024\/03\/25\/declaracion-publica-cruch\/","title":{"rendered":"Declaraci\u00f3n p\u00fablica CRUCH"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row][vc_column]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\"><span itemprop=\"name\">Escuela de Ingenieria<\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Declaraci\u00f3n p\u00fablica CRUCH <\/span><meta itemprop=\"position\" content=\"3\" \/><\/ol><\/div><ul class=\"p-0 list-style-none d-inline-block\"><li class=\"p-0\"><a href=https:\/\/www.uoh.cl\/escuela-de-ingenieria\/category\/institucional\/ class=\"px-1 py-2\">Institucional<\/a><\/li><\/ul><div class=\"date_publish_post\"> \u25cf Lun 25 de Marzo 2024<\/div><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block title--decorator  big\">Declaraci\u00f3n p\u00fablica CRUCH<\/h1><\/div>[vc_row_inner el_class=&#8221;border-separator m-0&#8243;][vc_column_inner width=&#8221;2\/3&#8243;]<div class=\"author_wp_class\"> Escrito por <span>Universidad de O'Higgins<\/span><\/div>[\/vc_column_inner][vc_column_inner el_class=&#8221;align-items-end-publish&#8221; width=&#8221;1\/3&#8243;]<div class=\"uoh_social_network_component uoh_row col-12 justify-content-end m-0 p-0\"> <div class=\"icon__facebook-share-button\">\n                       <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.uoh.cl\/escuela-de-ingenieria\/2024\/03\/25\/declaracion-publica-cruch\/\" target=\"_blank\"> <div class=\"icon__facebook-svg\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22.4px\" height=\"48.3px\" viewBox=\"0 0 22.4 48.3\" style=\"overflow:visible;enable-background:new 0 0 22.4 48.3;\" xml:space=\"preserve\">\n                <defs>\n                <\/defs>\n                <path class=\"st0\" d=\"M22.4,15.6h-7.6v-5c0-1.9,1.2-2.3,2.1-2.3c0.9,0,5.4,0,5.4,0V0l-7.4,0C6.6,0,4.8,6.2,4.8,10.1v5.5H0v8.5h4.8\n                    c0,10.9,0,24.1,0,24.1h10c0,0,0-13.3,0-24.1h6.8L22.4,15.6z\"><\/path>\n                <\/svg><\/a><\/div>\n                    <\/div><div class=\"icon__twitter-share-button\">\n                        <div class=\"icon__twitter-svg\"><a target=\"_blank\" href=\"http:\/\/twitter.com\/share?url=https:\/\/www.uoh.cl\/escuela-de-ingenieria\/2024\/03\/25\/declaracion-publica-cruch\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/a><\/div>\n                        <\/div><div class=\"icon__linkedin-share-button\">\n                        <div class=\"icon__linkedin-svg\">\n                        <a target=\"__blank\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.uoh.cl\/escuela-de-ingenieria\/2024\/03\/25\/declaracion-publica-cruch\/\"><svg enable-background=\"new 0 0 100 100\" height=\"100px\" id=\"Layer_1\" version=\"1.1\" viewBox=\"0 0 100 100\" width=\"100px\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><circle cx=\"50\" cy=\"50\" fill=\"#ccc\" r=\"45\"\/><g id=\"LinkedIn_1_\"><rect fill=\"#FFFFFF\" height=\"24.361\" width=\"7.69\" x=\"31.271\" y=\"43.569\"\/><path d=\"M59.968,43.334c-4.406,0-7.165,2.387-7.677,4.058v-3.823h-8.636c0.109,2.03,0,24.361,0,24.361h8.636    V54.748c0-0.733-0.034-1.465,0.19-1.991c0.594-1.464,1.869-2.985,4.162-2.985c2.998,0,4.361,2.253,4.361,5.552V67.93h8.721V54.384    C69.726,46.839,65.432,43.334,59.968,43.334z\" fill=\"#FFFFFF\"\/><path d=\"M34.973,32.069c-2.839,0-4.696,1.823-4.696,4.229c0,2.361,1.804,4.224,4.589,4.224h0.054    c2.891,0,4.69-1.869,4.69-4.229C39.555,33.888,37.81,32.069,34.973,32.069z\" fill=\"#FFFFFF\"\/><\/g><\/g><\/svg><\/a><\/div>\n\n            <\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_single_image image=&#8221;32036&#8243; img_size=&#8221;full&#8221; add_caption=&#8221;yes&#8221; alignment=&#8221;center&#8221; onclick=&#8221;img_link_large&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]\u00a0[\/vc_column_text][vc_column_text]<\/p>\n<ul>\n<li><em>&#8220;Como Consejo, manifestamos nuestro desacuerdo con esta impugnaci\u00f3n, puesto que los valores ciudadanos de libertad de ense\u00f1anza y el derecho de madres y padres a definir la educaci\u00f3n de hijas e hijos, no est\u00e1n en contradicci\u00f3n con los derechos y la dignidad de mujeres y hombres&#8221;.<\/em><\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_column_text]\u00a0[\/vc_column_text][vc_column_text]El Consejo de Rectoras y Rectores de las Universidades Chilenas (CRUCH) valora que la Ley sobre el Derecho de las Mujeres a una Vida Libre de Violencia haya sido despachada el 6 de marzo pasado, luego de siete a\u00f1os de tramitaci\u00f3n en el Congreso Nacional.<\/p>\n<p>Las 30 universidades que forman parte del CRUCH, desde hace a\u00f1os han estado comprometidas con promover la equidad de g\u00e9nero y la erradicaci\u00f3n de la discriminaci\u00f3n arbitraria y la violencia contra las mujeres.<\/p>\n<p>Uno de los aspectos expl\u00edcitos del texto legal es la educaci\u00f3n no sexista, como se establece en el inciso segundo del art\u00edculo 12: &#8220;Los establecimientos educacionales reconocidos por el Estado deber\u00e1n promover una educaci\u00f3n no sexista y con igualdad de g\u00e9nero y considerar en sus reglamentos internos y protocolos la promoci\u00f3n de la igualdad en dignidad y derechos y la prevenci\u00f3n de la violencia de g\u00e9nero en todas sus formas&#8221;.<\/p>\n<p>En relaci\u00f3n a una parte de este inciso, el pasado 8 de marzo un grupo de parlamentarios solicit\u00f3 al Tribunal Constitucional que declare su inaplicabilidad, argumentando que la educaci\u00f3n no sexista atenta contra el derecho preferente de madres y padres a elegir la educaci\u00f3n de sus hijas e hijos y contra la libertad de ense\u00f1anza.<\/p>\n<p>Como Consejo, manifestamos nuestro desacuerdo con esta impugnaci\u00f3n, puesto que los valores ciudadanos de libertad de ense\u00f1anza y el derecho de madres y padres a definir la educaci\u00f3n de hijas e hijos, no est\u00e1n en contradicci\u00f3n con los derechos y la dignidad de mujeres y hombres.<\/p>\n<p>En realidad, la educaci\u00f3n no sexista no promueve un enfoque \u00fanico de ense\u00f1anza ni pretende imponer convicciones morales o religiosas. Por el contrario, propone un cuerpo t\u00e9cnico y metodol\u00f3gico que permite tratar a las comunidades educativas con igualdad de g\u00e9nero y no discriminaci\u00f3n y, al mismo tiempo, elimina brechas y estereotipos de g\u00e9nero existentes.<\/p>\n<p>Como CRUCH valoramos la diversidad de proyectos educativos, puesto que tal diversidad es una fortaleza del sistema. A su turno, la educaci\u00f3n no sexista constituye un derecho humano y responde a principios compartidos por la sociedad en lo referido a la igualdad y no discriminaci\u00f3n. Por lo tanto, en ning\u00fan caso, cumplir con principios y valores universales puede atentar contra la diversidad.<\/p>\n<p>En este contexto, las universidades pertenecientes al Consejo de Rectoras y Rectores consideramos oportuno reafirmar y hacer p\u00fablico nuestro compromiso con la igualdad de g\u00e9nero y de derechos para todas las personas, reconociendo su dignidad esencial, con independencia de credo, edad, clase social, cultura, g\u00e9nero u orientaci\u00f3n sexual, lengua y condici\u00f3n.<\/p>\n<p>Para lograr lo anterior y superar la discriminaci\u00f3n arbitraria, las inequidades, los estereotipos y las jerarqu\u00edas de g\u00e9nero, es indispensable que se asegure una educaci\u00f3n no sexista en todos los niveles educativos. En consecuencia, estimamos imprescindible que ello quede establecido en forma expl\u00edcita en la Ley sobre el Derecho de las Mujeres a una Vida Libre de Violencia.<\/p>\n<p><strong>Consejo de Rectoras y Rectores de las Universidades Chilenas<\/strong>[\/vc_column_text][vc_zigzag color=&#8221;white&#8221;][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650255686594{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center p-md-0 pt-5 pb-5&#8243;][vc_column el_class=&#8221;pb-5&#8243;][vc_row_inner el_class=&#8221;pb-5&#8243;][vc_column_inner]<div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0\"><h2 class=\"title title--decorator title--ms d-inline-block\">Te Recomendamos<\/h2><\/div><\/div><div class=\"content-holder\"><div class=\"row  swipper-news-list not--activate-hack \"><div class=\"row -wrapper\"><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-content\/uploads\/sites\/15\/2026\/04\/Inauguracion-Ano-Academico-2026-6.jpg\" alt=\"Reflexi\u00f3n universitaria: UOH inaugura A\u00f1o Acad\u00e9mico 2026 pensando en los desaf\u00edos de la Educaci\u00f3n Superior\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Mi\u00e9rcoles 29, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/2026\/04\/29\/reflexion-universitaria-uoh-inaugura-ano-academico-2026-pensando-en-los-desafios-de-la-educacion-superior\/\">\n                                    <h3 class=\"small-space\">Reflexi\u00f3n universitaria: UOH inaugura A\u00f1o Acad\u00e9mico 2026 pensando en los desaf\u00edos de la Educaci\u00f3n Superior<\/h3><\/a>\n\n                                    <p>La ceremonia promovi\u00f3 el an\u00e1lisis acerca de los cambios educativos que se avecinan dentro de los procesos de formaci\u00f3n universitaria ajustados a contextos digitales.   <\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/2026\/04\/29\/reflexion-universitaria-uoh-inaugura-ano-academico-2026-pensando-en-los-desafios-de-la-educacion-superior\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/category\/investigacion\/\">\n                                        Investigaci\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-content\/uploads\/sites\/15\/2026\/04\/SOLEDAD-BURRONE-EVALUANDO-1.jpg\" alt=\"Ciencia desde el aula: m\u00e1s de 40 proyectos se presentaron en el II Congreso de Investigaci\u00f3n de Estudiantes UOH\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Viernes 24, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/2026\/04\/24\/ciencia-desde-el-aula-mas-de-40-proyectos-se-presentaron-en-el-ii-congreso-de-investigacion-de-estudiantes-uoh\/\">\n                                    <h3 class=\"small-space\">Ciencia desde el aula: m\u00e1s de 40 proyectos se presentaron en el II Congreso de Investigaci\u00f3n de Estudiantes UOH<\/h3><\/a>\n\n                                    <p>La actividad reuni\u00f3 a estudiantes de pregrado y postgrado de las cinco escuelas e institutos de la Universidad de O\u2019Higgins, quienes expusieron sus trabajos en formato p\u00f3ster en diversas \u00e1reas del conocimiento.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/2026\/04\/24\/ciencia-desde-el-aula-mas-de-40-proyectos-se-presentaron-en-el-ii-congreso-de-investigacion-de-estudiantes-uoh\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/category\/ingenieria\/\">\n                                        Ingenier\u00eda<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-content\/uploads\/sites\/15\/2026\/04\/FIDAE-2.jpeg\" alt=\"Estudiantes de la Escuela de Ingenier\u00eda UOH viven experiencia formativa en FIDAE 2026\" style=\"--smush-placeholder-width: 1600px; --smush-placeholder-aspect-ratio: 1600\/1200;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Mi\u00e9rcoles 15, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/2026\/04\/15\/estudiantes-de-la-escuela-de-ingenieria-uoh-viven-experiencia-formativa-en-fidae-2026\/\">\n                                    <h3 class=\"small-space\">Estudiantes de la Escuela de Ingenier\u00eda UOH viven experiencia formativa en FIDAE 2026<\/h3><\/a>\n\n                                    <p>La actividad permiti\u00f3 a estudiantes conocer avances tecnol\u00f3gicos y vincularse con actores clave de la industria. <\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/2026\/04\/15\/estudiantes-de-la-escuela-de-ingenieria-uoh-viven-experiencia-formativa-en-fidae-2026\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pagination justify-content-center my-5\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-json\/wp\/v2\/posts\/1929\/\/page\/2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-json\/wp\/v2\/posts\/1929\/\/page\/3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-json\/wp\/v2\/posts\/1929\/\/page\/137\">137<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-json\/wp\/v2\/posts\/1929\/\/page\/2\"><div class=\"icon-pagination-next\"> <?xml version=\"1.0\" ?><svg viewBox=\"0 0 96 96\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><title\/><path d=\"M39.3756,48.0022l30.47-25.39a6.0035,6.0035,0,0,0-7.6878-9.223L26.1563,43.3906a6.0092,6.0092,0,0,0,0,9.2231L62.1578,82.615a6.0035,6.0035,0,0,0,7.6878-9.2231Z\"\/><\/svg> <\/div><\/a><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>&#8220;La educaci\u00f3n no sexista no promueve un enfoque \u00fanico de ense\u00f1anza ni pretende imponer convicciones morales o religiosas. Por el contrario, propone un cuerpo t\u00e9cnico y metodol\u00f3gico que permite tratar a las comunidades educativas con igualdad de g\u00e9nero y no discriminaci\u00f3n y, al mismo tiempo, elimina brechas y estereotipos de g\u00e9nero existentes&#8221;.<\/p>\n","protected":false},"author":34,"featured_media":1932,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucional"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Declaraci\u00f3n p\u00fablica CRUCH - Escuela de Ingenieria<\/title>\n<meta name=\"description\" content=\"La acad\u00e9mica UOH Mar\u00eda Teresa Sol\u00eds apunta a las estrategias de prevenci\u00f3n de este tipo de c\u00e1ncer, que fueron descuidadas por la poblaci\u00f3n tras la Pandemia de Covid.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Declaraci\u00f3n p\u00fablica CRUCH - Escuela de Ingenieria\" \/>\n<meta property=\"og:description\" content=\"La acad\u00e9mica UOH Mar\u00eda Teresa Sol\u00eds apunta a las estrategias de prevenci\u00f3n de este tipo de c\u00e1ncer, que fueron descuidadas por la poblaci\u00f3n tras la Pandemia de Covid.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/2024\/03\/25\/declaracion-publica-cruch\/\" \/>\n<meta property=\"og:site_name\" content=\"Escuela de Ingenieria\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-25T18:59:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-26T12:08:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-content\/uploads\/sites\/15\/2024\/03\/Logo-cruch-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Universidad de O&#039;Higgins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Universidad de O&#039;Higgins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/2024\/03\/25\/declaracion-publica-cruch\/\",\"url\":\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/2024\/03\/25\/declaracion-publica-cruch\/\",\"name\":\"Declaraci\u00f3n p\u00fablica CRUCH - Escuela de Ingenieria\",\"isPartOf\":{\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/2024\/03\/25\/declaracion-publica-cruch\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/2024\/03\/25\/declaracion-publica-cruch\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-content\/uploads\/sites\/15\/2024\/03\/Logo-cruch-1.jpg\",\"datePublished\":\"2024-03-25T18:59:13+00:00\",\"dateModified\":\"2024-03-26T12:08:39+00:00\",\"author\":{\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"description\":\"La acad\u00e9mica UOH Mar\u00eda Teresa Sol\u00eds apunta a las estrategias de prevenci\u00f3n de este tipo de c\u00e1ncer, que fueron descuidadas por la poblaci\u00f3n tras la Pandemia de Covid.\",\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/2024\/03\/25\/declaracion-publica-cruch\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/2024\/03\/25\/declaracion-publica-cruch\/#primaryimage\",\"url\":\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-content\/uploads\/sites\/15\/2024\/03\/Logo-cruch-1.jpg\",\"contentUrl\":\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-content\/uploads\/sites\/15\/2024\/03\/Logo-cruch-1.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/#website\",\"url\":\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/\",\"name\":\"Escuela de Ingenieria\",\"description\":\"Otro sitio de Sitios de Universidad O'higgins\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\",\"name\":\"Universidad de O'Higgins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"caption\":\"Universidad de O'Higgins\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Declaraci\u00f3n p\u00fablica CRUCH - Escuela de Ingenieria","description":"La acad\u00e9mica UOH Mar\u00eda Teresa Sol\u00eds apunta a las estrategias de prevenci\u00f3n de este tipo de c\u00e1ncer, que fueron descuidadas por la poblaci\u00f3n tras la Pandemia de Covid.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Declaraci\u00f3n p\u00fablica CRUCH - Escuela de Ingenieria","og_description":"La acad\u00e9mica UOH Mar\u00eda Teresa Sol\u00eds apunta a las estrategias de prevenci\u00f3n de este tipo de c\u00e1ncer, que fueron descuidadas por la poblaci\u00f3n tras la Pandemia de Covid.","og_url":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/2024\/03\/25\/declaracion-publica-cruch\/","og_site_name":"Escuela de Ingenieria","article_published_time":"2024-03-25T18:59:13+00:00","article_modified_time":"2024-03-26T12:08:39+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-content\/uploads\/sites\/15\/2024\/03\/Logo-cruch-1.jpg","type":"image\/jpeg"}],"author":"Universidad de O'Higgins","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Universidad de O'Higgins","Tiempo estimado de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/2024\/03\/25\/declaracion-publica-cruch\/","url":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/2024\/03\/25\/declaracion-publica-cruch\/","name":"Declaraci\u00f3n p\u00fablica CRUCH - Escuela de Ingenieria","isPartOf":{"@id":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/2024\/03\/25\/declaracion-publica-cruch\/#primaryimage"},"image":{"@id":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/2024\/03\/25\/declaracion-publica-cruch\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-content\/uploads\/sites\/15\/2024\/03\/Logo-cruch-1.jpg","datePublished":"2024-03-25T18:59:13+00:00","dateModified":"2024-03-26T12:08:39+00:00","author":{"@id":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"description":"La acad\u00e9mica UOH Mar\u00eda Teresa Sol\u00eds apunta a las estrategias de prevenci\u00f3n de este tipo de c\u00e1ncer, que fueron descuidadas por la poblaci\u00f3n tras la Pandemia de Covid.","inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/escuela-de-ingenieria\/2024\/03\/25\/declaracion-publica-cruch\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/2024\/03\/25\/declaracion-publica-cruch\/#primaryimage","url":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-content\/uploads\/sites\/15\/2024\/03\/Logo-cruch-1.jpg","contentUrl":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-content\/uploads\/sites\/15\/2024\/03\/Logo-cruch-1.jpg","width":1000,"height":1000},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/#website","url":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/","name":"Escuela de Ingenieria","description":"Otro sitio de Sitios de Universidad O'higgins","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f","name":"Universidad de O'Higgins","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","caption":"Universidad de O'Higgins"}}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-json\/wp\/v2\/posts\/1929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-json\/wp\/v2\/comments?post=1929"}],"version-history":[{"count":1,"href":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-json\/wp\/v2\/posts\/1929\/revisions"}],"predecessor-version":[{"id":1931,"href":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-json\/wp\/v2\/posts\/1929\/revisions\/1931"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-json\/wp\/v2\/media\/1932"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-json\/wp\/v2\/media?parent=1929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-json\/wp\/v2\/categories?post=1929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-json\/wp\/v2\/tags?post=1929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}