
{"id":43,"count":8,"description":"","link":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/category\/cuech\/","name":"CUECH","slug":"cuech","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CUECH Archives - Escuela de Ingenieria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/category\/cuech\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CUECH Archives - Escuela de Ingenieria\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/category\/cuech\/\" \/>\n<meta property=\"og:site_name\" content=\"Escuela de Ingenieria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/category\/cuech\/\",\"url\":\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/category\/cuech\/\",\"name\":\"CUECH Archives - Escuela de Ingenieria\",\"isPartOf\":{\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/#website\"},\"inLanguage\":\"es-CL\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/#website\",\"url\":\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/\",\"name\":\"Escuela de Ingenieria\",\"description\":\"Otro sitio de Sitios de Universidad O'higgins\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CUECH Archives - Escuela de Ingenieria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/category\/cuech\/","og_locale":"es_ES","og_type":"article","og_title":"CUECH Archives - Escuela de Ingenieria","og_url":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/category\/cuech\/","og_site_name":"Escuela de Ingenieria","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/category\/cuech\/","url":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/category\/cuech\/","name":"CUECH Archives - Escuela de Ingenieria","isPartOf":{"@id":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/#website"},"inLanguage":"es-CL"},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/#website","url":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/","name":"Escuela de Ingenieria","description":"Otro sitio de Sitios de Universidad O'higgins","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-json\/wp\/v2\/categories\/43","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.uoh.cl\/escuela-de-ingenieria\/wp-json\/wp\/v2\/posts?categories=43"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}