
{"id":4628,"date":"2026-05-27T16:19:16","date_gmt":"2026-05-27T19:19:16","guid":{"rendered":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/27\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\/"},"modified":"2026-05-27T16:19:16","modified_gmt":"2026-05-27T19:19:16","slug":"estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares","status":"publish","type":"post","link":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/27\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\/","title":{"rendered":"Estudiantes de Pedagog\u00eda en Lenguaje y Comunicaci\u00f3n participaron en taller sobre narraci\u00f3n oral y cuentos populares"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row][vc_column]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\"><span itemprop=\"name\">Escuela de Educaci\u00f3n <\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/noticias\/\"><span itemprop=\"name\">Noticias<\/span><\/a><meta itemprop=\"position\" content=\"3\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Estudiantes de Pedagog\u00eda en Lenguaje y Comunicaci\u00f3n participaron en taller <\/span><meta itemprop=\"position\" content=\"4\" \/><\/ol><\/div><ul class=\"p-0 list-style-none d-inline-block\"><li class=\"p-0\"><a href=https:\/\/www.uoh.cl\/escuela-de-educacion\/category\/educacion\/ class=\"px-1 py-2\">Educaci\u00f3n<\/a><\/li><\/ul><div class=\"date_publish_post\"> \u25cf Mi\u00e9 27 de Mayo 2026<\/div><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block title--decorator  big\">Estudiantes de Pedagog\u00eda en Lenguaje y Comunicaci\u00f3n participaron en taller sobre narraci\u00f3n oral y cuentos populares<\/h1><\/div>[vc_row_inner el_class=&#8221;border-separator m-0&#8243;][vc_column_inner width=&#8221;2\/3&#8243;]<div class=\"author_wp_class\"> Escrito por <span>Universidad de O'Higgins<\/span><\/div>[\/vc_column_inner][vc_column_inner el_class=&#8221;align-items-end-publish&#8221; width=&#8221;1\/3&#8243;]<div class=\"uoh_social_network_component uoh_row col-12 justify-content-end m-0 p-0\"> <div class=\"icon__facebook-share-button\">\n                       <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/27\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\/\" target=\"_blank\"> <div class=\"icon__facebook-svg\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22.4px\" height=\"48.3px\" viewBox=\"0 0 22.4 48.3\" style=\"overflow:visible;enable-background:new 0 0 22.4 48.3;\" xml:space=\"preserve\">\n                <defs>\n                <\/defs>\n                <path class=\"st0\" d=\"M22.4,15.6h-7.6v-5c0-1.9,1.2-2.3,2.1-2.3c0.9,0,5.4,0,5.4,0V0l-7.4,0C6.6,0,4.8,6.2,4.8,10.1v5.5H0v8.5h4.8\n                    c0,10.9,0,24.1,0,24.1h10c0,0,0-13.3,0-24.1h6.8L22.4,15.6z\"><\/path>\n                <\/svg><\/a><\/div>\n                    <\/div><div class=\"icon__twitter-share-button\">\n                        <div class=\"icon__twitter-svg\"><a target=\"_blank\" href=\"http:\/\/twitter.com\/share?url=https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/27\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/a><\/div>\n                        <\/div><div class=\"icon__linkedin-share-button\">\n                        <div class=\"icon__linkedin-svg\">\n                        <a target=\"__blank\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/27\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\/\"><svg enable-background=\"new 0 0 100 100\" height=\"100px\" id=\"Layer_1\" version=\"1.1\" viewBox=\"0 0 100 100\" width=\"100px\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><circle cx=\"50\" cy=\"50\" fill=\"#ccc\" r=\"45\"\/><g id=\"LinkedIn_1_\"><rect fill=\"#FFFFFF\" height=\"24.361\" width=\"7.69\" x=\"31.271\" y=\"43.569\"\/><path d=\"M59.968,43.334c-4.406,0-7.165,2.387-7.677,4.058v-3.823h-8.636c0.109,2.03,0,24.361,0,24.361h8.636    V54.748c0-0.733-0.034-1.465,0.19-1.991c0.594-1.464,1.869-2.985,4.162-2.985c2.998,0,4.361,2.253,4.361,5.552V67.93h8.721V54.384    C69.726,46.839,65.432,43.334,59.968,43.334z\" fill=\"#FFFFFF\"\/><path d=\"M34.973,32.069c-2.839,0-4.696,1.823-4.696,4.229c0,2.361,1.804,4.224,4.589,4.224h0.054    c2.891,0,4.69-1.869,4.69-4.229C39.555,33.888,37.81,32.069,34.973,32.069z\" fill=\"#FFFFFF\"\/><\/g><\/g><\/svg><\/a><\/div>\n\n            <\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_single_image image=&#8221;76570&#8243; img_size=&#8221;1500&#215;1000&#8243; add_caption=&#8221;yes&#8221; alignment=&#8221;center&#8221; onclick=&#8221;img_link_large&#8221; css=&#8221;&#8221;][vc_column_text]\u00a0[\/vc_column_text][vc_column_text css=&#8221;&#8221;]<\/p>\n<ul>\n<li><em>La actividad abord\u00f3 herramientas te\u00f3ricas y metodol\u00f3gicas para la ense\u00f1anza de la narraci\u00f3n oral en contextos educativos.<\/em><\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_column_text]\u00a0[\/vc_column_text][vc_column_text css=&#8221;&#8221;]La narraci\u00f3n oral, la literatura y la representaci\u00f3n esc\u00e9nica se unieron en una actividad desarrollada para estudiantes de segundo a\u00f1o de <a href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/carreras\/pedagogia-en-lenguaje-y-comunicacion\/\">Pedagog\u00eda en Lenguaje y Comunicaci\u00f3n<\/a> de la <a href=\"http:\/\/www.uoh.cl\/\">Universidad de O&#8217;Higgins<\/a>, quienes participaron en el taller \u201c\u00c9pica, drama y maravilla en los cuentos populares para la infancia: aportes te\u00f3rico-metodol\u00f3gicos para una did\u00e1ctica de la narraci\u00f3n oral\u201d.<\/p>\n<p>La instancia fue dictada por Patricio Gonz\u00e1lez en el marco del curso \u201cTeor\u00eda Literaria\u201d del docente Mauricio G\u00f3mez y cont\u00f3 adem\u00e1s con la participaci\u00f3n de Jorge Miranda, quien colabor\u00f3 en el dise\u00f1o de la experiencia desarrollada junto a las\/os estudiantes.<\/p>\n<p>La actividad contempl\u00f3 una primera etapa te\u00f3rica enfocada en la estructura del cuento cl\u00e1sico propuesta por el te\u00f3rico ruso Vladimir Propp, para posteriormente trasladar esos contenidos a un ejercicio pr\u00e1ctico de creaci\u00f3n y representaci\u00f3n narrativa.<\/p>\n<p>Durante el taller, quienes participaron trabajaron en la planificaci\u00f3n de distintos guiones elaborados a partir de relatos entregados por los asistentes, organizando posteriormente las escenas y momentos narrativos dentro del espacio esc\u00e9nico.<\/p>\n<p>A trav\u00e9s de dramatizaciones grupales, las\/os estudiantes pudieron observar c\u00f3mo los cuentos cl\u00e1sicos incorporan distintos elementos narrativos, manteniendo al mismo tiempo estructuras fundamentales presentes en este tipo de relatos.<\/p>\n<p>La experiencia permiti\u00f3 vincular contenidos propios de los estudios literarios con estrategias did\u00e1cticas aplicables en el sistema educativo, promoviendo adem\u00e1s herramientas \u00fatiles para la planificaci\u00f3n y creaci\u00f3n literaria en contextos pedag\u00f3gicos.<\/p>\n<p>Mauricio G\u00f3mez destac\u00f3 el valor de incorporar experiencias pr\u00e1cticas en la formaci\u00f3n de futuros docentes de Lenguaje y Comunicaci\u00f3n. \u201cEste tipo de talleres permite que las\/os estudiantes no solo comprendan conceptos te\u00f3ricos vinculados a la literatura y la narraci\u00f3n oral, sino que tambi\u00e9n puedan experimentarlos desde la creaci\u00f3n, la puesta en escena y el trabajo colaborativo\u201d, se\u00f1al\u00f3.<\/p>\n<p>Adem\u00e1s, explic\u00f3 que la actividad busc\u00f3 vincular herramientas de los estudios literarios con metodolog\u00edas aplicables en el aula. \u201cLa idea es que las\/os futuras\/os profesoras\/es puedan reconocer estas estructuras narrativas y luego transferirlas a contextos educativos, utilizando la narraci\u00f3n oral y la dramatizaci\u00f3n como recursos pedag\u00f3gicos significativos\u201d, a\u00f1adi\u00f3.[\/vc_column_text][vc_zigzag color=&#8221;white&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;76572&#8243; img_size=&#8221;700&#215;450&#8243; onclick=&#8221;link_image&#8221; css=&#8221;&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;76571&#8243; img_size=&#8221;700&#215;450&#8243; onclick=&#8221;link_image&#8221; css=&#8221;&#8221;][\/vc_column_inner][\/vc_row_inner][vc_zigzag color=&#8221;white&#8221;][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650255686594{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center p-md-0 pt-5 pb-5&#8243;][vc_column el_class=&#8221;pb-5&#8243;][vc_row_inner el_class=&#8221;pb-5&#8243;][vc_column_inner]<div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0\"><h2 class=\"title title--decorator title--ms d-inline-block\">Te Recomendamos<\/h2><\/div><\/div><div class=\"content-holder\"><div class=\"row  swipper-news-list not--activate-hack \"><div class=\"row -wrapper\"><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/category\/educacion\/\">\n                                        Educaci\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2026\/07\/Estudiantes-de-Pedagogia-UOH-inspiran-a-futuras-generaciones-de-docentes-en-encuentro-del-Programa-Vocacion-Pedagogica-2.jpeg\" alt=\"Estudiantes de Pedagog\u00eda UOH inspiran a futuras generaciones de docentes en encuentro del Programa Vocaci\u00f3n Pedag\u00f3gica\" style=\"--smush-placeholder-width: 1600px; --smush-placeholder-aspect-ratio: 1600\/1200;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Mi\u00e9rcoles 8, Julio<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/07\/08\/estudiantes-de-pedagogia-uoh-inspiran-a-futuras-generaciones-de-docentes-en-encuentro-del-programa-vocacion-pedagogica\/\">\n                                    <h3 class=\"small-space\">Estudiantes de Pedagog\u00eda UOH inspiran a futuras generaciones de docentes en encuentro del Programa Vocaci\u00f3n Pedag\u00f3gica<\/h3><\/a>\n\n                                    <p>A trav\u00e9s de un espacio de conversaci\u00f3n e intercambio de experiencias, estudiantes resolvieron dudas y acercaron la realidad de la formaci\u00f3n inicial docente a j\u00f3venes con inter\u00e9s en seguir esta profesi\u00f3n.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/07\/08\/estudiantes-de-pedagogia-uoh-inspiran-a-futuras-generaciones-de-docentes-en-encuentro-del-programa-vocacion-pedagogica\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/category\/educacion\/\">\n                                        Educaci\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2026\/07\/Pedagogia-en-Educacion-Basica-fortalece-la-formacion-docente-con-webinar-internacional-junto-a-la-Universidad-de-Brasilia-.png\" alt=\"Pedagog\u00eda en Educaci\u00f3n B\u00e1sica fortalece la formaci\u00f3n docente con webinar internacional junto a la Universidad de Brasilia\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Martes 7, Julio<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/07\/07\/pedagogia-en-educacion-basica-fortalece-la-formacion-docente-con-webinar-internacional-junto-a-la-universidad-de-brasilia\/\">\n                                    <h3 class=\"small-space\">Pedagog\u00eda en Educaci\u00f3n B\u00e1sica fortalece la formaci\u00f3n docente con webinar internacional junto a la Universidad de Brasilia<\/h3><\/a>\n\n                                    <p>La instancia permiti\u00f3 que estudiantes y acad\u00e9micas\/os de ambas universidades compartieran experiencias sobre literatura infantil, mediaci\u00f3n lectora y formaci\u00f3n de profesores<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/07\/07\/pedagogia-en-educacion-basica-fortalece-la-formacion-docente-con-webinar-internacional-junto-a-la-universidad-de-brasilia\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/category\/educacion\/\">\n                                        Educaci\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2026\/06\/Lanzamiento-Manual-cuando-el-curriculum-impacta-en-las-escuelas-1.jpg\" alt=\"UOH lanz\u00f3 innovador manual para promover la inclusi\u00f3n de estudiantes LGBTIQA+ en las escuelas\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Viernes 26, Junio<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/06\/26\/uoh-lanzo-innovador-manual-para-promover-la-inclusion-de-estudiantes-lgbtiqa-en-las-escuelas\/\">\n                                    <h3 class=\"small-space\">UOH lanz\u00f3 innovador manual para promover la inclusi\u00f3n de estudiantes LGBTIQA+ en las escuelas<\/h3><\/a>\n\n                                    <p>Es parte de un Proyecto de Innovaci\u00f3n en Docencia financiado por la Universidad de O'Higgins.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/06\/26\/uoh-lanzo-innovador-manual-para-promover-la-inclusion-de-estudiantes-lgbtiqa-en-las-escuelas\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pagination justify-content-center my-5\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/posts\/4628\/\/page\/2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/posts\/4628\/\/page\/3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/posts\/4628\/\/page\/164\">164<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/posts\/4628\/\/page\/2\"><div class=\"icon-pagination-next\"> <?xml version=\"1.0\" ?><svg viewBox=\"0 0 96 96\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><title\/><path d=\"M39.3756,48.0022l30.47-25.39a6.0035,6.0035,0,0,0-7.6878-9.223L26.1563,43.3906a6.0092,6.0092,0,0,0,0,9.2231L62.1578,82.615a6.0035,6.0035,0,0,0,7.6878-9.2231Z\"\/><\/svg> <\/div><\/a><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La actividad abord\u00f3 herramientas te\u00f3ricas y metodol\u00f3gicas para la ense\u00f1anza de la narraci\u00f3n oral en contextos educativos. <\/p>\n","protected":false},"author":34,"featured_media":4629,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[25],"tags":[],"class_list":["post-4628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estudiantes de Pedagog\u00eda en Lenguaje y Comunicaci\u00f3n participaron en taller sobre narraci\u00f3n oral y cuentos populares - Escuela de Educaci\u00f3n<\/title>\n<meta name=\"description\" content=\"La actividad abord\u00f3 herramientas te\u00f3ricas y metodol\u00f3gicas para la ense\u00f1anza de la narraci\u00f3n oral en contextos educativos.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estudiantes de Pedagog\u00eda en Lenguaje y Comunicaci\u00f3n participaron en taller sobre narraci\u00f3n oral y cuentos populares - Escuela de Educaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"La actividad abord\u00f3 herramientas te\u00f3ricas y metodol\u00f3gicas para la ense\u00f1anza de la narraci\u00f3n oral en contextos educativos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/27\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\/\" \/>\n<meta property=\"og:site_name\" content=\"Escuela de Educaci\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-27T19:19:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2026\/05\/Estudiantes-de-Pedagogia-en-Lenguaje-y-Comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Universidad de O&#039;Higgins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Universidad de O&#039;Higgins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-educacion\\\/2026\\\/05\\\/27\\\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-educacion\\\/2026\\\/05\\\/27\\\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\\\/\"},\"author\":{\"name\":\"Universidad de O'Higgins\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-educacion\\\/#\\\/schema\\\/person\\\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"headline\":\"Estudiantes de Pedagog\u00eda en Lenguaje y Comunicaci\u00f3n participaron en taller sobre narraci\u00f3n oral y cuentos populares\",\"datePublished\":\"2026-05-27T19:19:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-educacion\\\/2026\\\/05\\\/27\\\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\\\/\"},\"wordCount\":690,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-educacion\\\/2026\\\/05\\\/27\\\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-educacion\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2026\\\/05\\\/Estudiantes-de-Pedagogia-en-Lenguaje-y-Comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares-1.png\",\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-educacion\\\/2026\\\/05\\\/27\\\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-educacion\\\/2026\\\/05\\\/27\\\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\\\/\",\"url\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-educacion\\\/2026\\\/05\\\/27\\\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\\\/\",\"name\":\"Estudiantes de Pedagog\u00eda en Lenguaje y Comunicaci\u00f3n participaron en taller sobre narraci\u00f3n oral y cuentos populares - Escuela de Educaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-educacion\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-educacion\\\/2026\\\/05\\\/27\\\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-educacion\\\/2026\\\/05\\\/27\\\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-educacion\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2026\\\/05\\\/Estudiantes-de-Pedagogia-en-Lenguaje-y-Comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares-1.png\",\"datePublished\":\"2026-05-27T19:19:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-educacion\\\/#\\\/schema\\\/person\\\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"description\":\"La actividad abord\u00f3 herramientas te\u00f3ricas y metodol\u00f3gicas para la ense\u00f1anza de la narraci\u00f3n oral en contextos educativos.\",\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-educacion\\\/2026\\\/05\\\/27\\\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-educacion\\\/2026\\\/05\\\/27\\\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-educacion\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2026\\\/05\\\/Estudiantes-de-Pedagogia-en-Lenguaje-y-Comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares-1.png\",\"contentUrl\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-educacion\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2026\\\/05\\\/Estudiantes-de-Pedagogia-en-Lenguaje-y-Comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares-1.png\",\"width\":1500,\"height\":1000},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-educacion\\\/#website\",\"url\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-educacion\\\/\",\"name\":\"Escuela de Educaci\u00f3n\",\"description\":\"Otro sitio de Sitios de Universidad O'higgins\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-educacion\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/escuela-de-educacion\\\/#\\\/schema\\\/person\\\/ea242e676c7d6d7e46fc8b9e39486c4f\",\"name\":\"Universidad de O'Higgins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"caption\":\"Universidad de O'Higgins\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estudiantes de Pedagog\u00eda en Lenguaje y Comunicaci\u00f3n participaron en taller sobre narraci\u00f3n oral y cuentos populares - Escuela de Educaci\u00f3n","description":"La actividad abord\u00f3 herramientas te\u00f3ricas y metodol\u00f3gicas para la ense\u00f1anza de la narraci\u00f3n oral en contextos educativos.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Estudiantes de Pedagog\u00eda en Lenguaje y Comunicaci\u00f3n participaron en taller sobre narraci\u00f3n oral y cuentos populares - Escuela de Educaci\u00f3n","og_description":"La actividad abord\u00f3 herramientas te\u00f3ricas y metodol\u00f3gicas para la ense\u00f1anza de la narraci\u00f3n oral en contextos educativos.","og_url":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/27\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\/","og_site_name":"Escuela de Educaci\u00f3n","article_published_time":"2026-05-27T19:19:16+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2026\/05\/Estudiantes-de-Pedagogia-en-Lenguaje-y-Comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares-1.png","type":"image\/png"}],"author":"Universidad de O'Higgins","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Universidad de O'Higgins","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/27\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\/#article","isPartOf":{"@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/27\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\/"},"author":{"name":"Universidad de O'Higgins","@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"headline":"Estudiantes de Pedagog\u00eda en Lenguaje y Comunicaci\u00f3n participaron en taller sobre narraci\u00f3n oral y cuentos populares","datePublished":"2026-05-27T19:19:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/27\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\/"},"wordCount":690,"commentCount":0,"image":{"@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/27\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2026\/05\/Estudiantes-de-Pedagogia-en-Lenguaje-y-Comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares-1.png","articleSection":["Educaci\u00f3n"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/27\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/27\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\/","url":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/27\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\/","name":"Estudiantes de Pedagog\u00eda en Lenguaje y Comunicaci\u00f3n participaron en taller sobre narraci\u00f3n oral y cuentos populares - Escuela de Educaci\u00f3n","isPartOf":{"@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/27\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\/#primaryimage"},"image":{"@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/27\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2026\/05\/Estudiantes-de-Pedagogia-en-Lenguaje-y-Comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares-1.png","datePublished":"2026-05-27T19:19:16+00:00","author":{"@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"description":"La actividad abord\u00f3 herramientas te\u00f3ricas y metodol\u00f3gicas para la ense\u00f1anza de la narraci\u00f3n oral en contextos educativos.","inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/27\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/27\/estudiantes-de-pedagogia-en-lenguaje-y-comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares\/#primaryimage","url":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2026\/05\/Estudiantes-de-Pedagogia-en-Lenguaje-y-Comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares-1.png","contentUrl":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2026\/05\/Estudiantes-de-Pedagogia-en-Lenguaje-y-Comunicacion-participaron-en-taller-sobre-narracion-oral-y-cuentos-populares-1.png","width":1500,"height":1000},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/#website","url":"https:\/\/www.uoh.cl\/escuela-de-educacion\/","name":"Escuela de Educaci\u00f3n","description":"Otro sitio de Sitios de Universidad O'higgins","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/escuela-de-educacion\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f","name":"Universidad de O'Higgins","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","caption":"Universidad de O'Higgins"}}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/posts\/4628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/comments?post=4628"}],"version-history":[{"count":0,"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/posts\/4628\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/media\/4629"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/media?parent=4628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/categories?post=4628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/tags?post=4628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}