
{"id":2247,"date":"2023-08-30T15:47:08","date_gmt":"2023-08-30T18:47:08","guid":{"rendered":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2023\/08\/30\/uoh-y-compromiso-con-la-educacion-casa-de-estudios-refuerza-vinculo-con-catedra-unesco-para-el-mejoramiento-de-la-lectura-y-la-escritura\/"},"modified":"2023-08-30T15:47:08","modified_gmt":"2023-08-30T18:47:08","slug":"uoh-y-compromiso-con-la-educacion-casa-de-estudios-refuerza-vinculo-con-catedra-unesco-para-el-mejoramiento-de-la-lectura-y-la-escritura","status":"publish","type":"post","link":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2023\/08\/30\/uoh-y-compromiso-con-la-educacion-casa-de-estudios-refuerza-vinculo-con-catedra-unesco-para-el-mejoramiento-de-la-lectura-y-la-escritura\/","title":{"rendered":"UOH y compromiso con la educaci\u00f3n: casa de estudios refuerza v\u00ednculo con C\u00e1tedra Unesco para el mejoramiento de la lectura y la escritura"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row][vc_column]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\"><span itemprop=\"name\">Escuela de Educaci\u00f3n <\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/noticias\/\"><span itemprop=\"name\">Noticias<\/span><\/a><meta itemprop=\"position\" content=\"3\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">UOH y compromiso con la educaci\u00f3n: casa de estudios refuerza <\/span><meta itemprop=\"position\" content=\"4\" \/><\/ol><\/div><ul class=\"p-0 list-style-none d-inline-block\"><li class=\"p-0\"><a href=https:\/\/www.uoh.cl\/escuela-de-educacion\/category\/educacion\/ class=\"px-1 py-2\">Educaci\u00f3n<\/a><\/li><\/ul><div class=\"date_publish_post\"> \u25cf Mi\u00e9 30 de Agosto 2023<\/div><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block title--decorator  big\">UOH y compromiso con la educaci\u00f3n: casa de estudios refuerza v\u00ednculo con C\u00e1tedra Unesco para el mejoramiento de la lectura y la escritura<\/h1><\/div>[vc_row_inner el_class=&#8221;border-separator m-0&#8243;][vc_column_inner width=&#8221;2\/3&#8243;]<div class=\"author_wp_class\"> Escrito por <span>Universidad de O'Higgins<\/span><\/div>[\/vc_column_inner][vc_column_inner el_class=&#8221;align-items-end-publish&#8221; width=&#8221;1\/3&#8243;]<div class=\"uoh_social_network_component uoh_row col-12 justify-content-end m-0 p-0\"> <div class=\"icon__facebook-share-button\">\n                       <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.uoh.cl\/escuela-de-educacion\/2023\/08\/30\/uoh-y-compromiso-con-la-educacion-casa-de-estudios-refuerza-vinculo-con-catedra-unesco-para-el-mejoramiento-de-la-lectura-y-la-escritura\/\" target=\"_blank\"> <div class=\"icon__facebook-svg\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22.4px\" height=\"48.3px\" viewBox=\"0 0 22.4 48.3\" style=\"overflow:visible;enable-background:new 0 0 22.4 48.3;\" xml:space=\"preserve\">\n                <defs>\n                <\/defs>\n                <path class=\"st0\" d=\"M22.4,15.6h-7.6v-5c0-1.9,1.2-2.3,2.1-2.3c0.9,0,5.4,0,5.4,0V0l-7.4,0C6.6,0,4.8,6.2,4.8,10.1v5.5H0v8.5h4.8\n                    c0,10.9,0,24.1,0,24.1h10c0,0,0-13.3,0-24.1h6.8L22.4,15.6z\"><\/path>\n                <\/svg><\/a><\/div>\n                    <\/div><div class=\"icon__twitter-share-button\">\n                        <div class=\"icon__twitter-svg\"><a target=\"_blank\" href=\"http:\/\/twitter.com\/share?url=https:\/\/www.uoh.cl\/escuela-de-educacion\/2023\/08\/30\/uoh-y-compromiso-con-la-educacion-casa-de-estudios-refuerza-vinculo-con-catedra-unesco-para-el-mejoramiento-de-la-lectura-y-la-escritura\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/a><\/div>\n                        <\/div><div class=\"icon__linkedin-share-button\">\n                        <div class=\"icon__linkedin-svg\">\n                        <a target=\"__blank\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.uoh.cl\/escuela-de-educacion\/2023\/08\/30\/uoh-y-compromiso-con-la-educacion-casa-de-estudios-refuerza-vinculo-con-catedra-unesco-para-el-mejoramiento-de-la-lectura-y-la-escritura\/\"><svg enable-background=\"new 0 0 100 100\" height=\"100px\" id=\"Layer_1\" version=\"1.1\" viewBox=\"0 0 100 100\" width=\"100px\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><circle cx=\"50\" cy=\"50\" fill=\"#ccc\" r=\"45\"\/><g id=\"LinkedIn_1_\"><rect fill=\"#FFFFFF\" height=\"24.361\" width=\"7.69\" x=\"31.271\" y=\"43.569\"\/><path d=\"M59.968,43.334c-4.406,0-7.165,2.387-7.677,4.058v-3.823h-8.636c0.109,2.03,0,24.361,0,24.361h8.636    V54.748c0-0.733-0.034-1.465,0.19-1.991c0.594-1.464,1.869-2.985,4.162-2.985c2.998,0,4.361,2.253,4.361,5.552V67.93h8.721V54.384    C69.726,46.839,65.432,43.334,59.968,43.334z\" fill=\"#FFFFFF\"\/><path d=\"M34.973,32.069c-2.839,0-4.696,1.823-4.696,4.229c0,2.361,1.804,4.224,4.589,4.224h0.054    c2.891,0,4.69-1.869,4.69-4.229C39.555,33.888,37.81,32.069,34.973,32.069z\" fill=\"#FFFFFF\"\/><\/g><\/g><\/svg><\/a><\/div>\n\n            <\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_single_image image=&#8221;22124&#8243; img_size=&#8221;full&#8221; add_caption=&#8221;yes&#8221; alignment=&#8221;center&#8221; onclick=&#8221;img_link_large&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]\u00a0[\/vc_column_text][vc_column_text]<\/p>\n<ul>\n<li><i>El acuerdo tiene como objetivo principal promover la alfabetizaci\u00f3n y el desarrollo de habilidades de lectura y escritura en la poblaci\u00f3n chilena, especialmente en aquellos grupos m\u00e1s vulnerables.<\/i><\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_column_text]\u00a0[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"font-weight: 400\">Uno de los objetivos de la <b><i>C\u00e1tedra Unesco para el mejoramiento de la lectura y la escritura <\/i><\/b>es mantener, profundizar y desarrollar actividades acad\u00e9micas, cient\u00edficas y t\u00e9cnicas conjuntas, que posibiliten el intercambio de conocimientos en el desarrollo institucional de la educaci\u00f3n superior. Tambi\u00e9n se declara el inter\u00e9s mutuo en el fortalecimiento democr\u00e1tico de los pa\u00edses de Am\u00e9rica Latina a trav\u00e9s de una educaci\u00f3n de calidad y equitativa, as\u00ed como la importancia del papel de la educaci\u00f3n superior en esta \u00e9poca de grandes transformaciones para el desarrollo cultural, socioecon\u00f3mico y ecol\u00f3gico de la regi\u00f3n.<\/p>\n<p style=\"font-weight: 400\">En el marco del primer\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=X67t3koFOlI&amp;ab_channel=UniversidaddeO%27Higgins\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.youtube.com\/watch?v%3DX67t3koFOlI%26ab_channel%3DUniversidaddeO%2527Higgins&amp;source=gmail&amp;ust=1693504868531000&amp;usg=AOvVaw1dDZmvkTUuPjDpL8fPpK1T\">Congreso Regional de Estudiantes de Pedagog\u00eda<\/a>, la\u00a0<a href=\"http:\/\/www.uoh.cl\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.uoh.cl\/&amp;source=gmail&amp;ust=1693504868531000&amp;usg=AOvVaw1n9DjPYHKsw56Rx2JHK0uy\">Universidad de O&#8217;Higgins<\/a>\u00a0reafirm\u00f3 su compromiso con la C\u00e1tedra Unesco buscando fomentar la investigaci\u00f3n y el intercambio de conocimientos sobre la ense\u00f1anza de la lectura y la escritura, as\u00ed como tambi\u00e9n el desarrollo de pol\u00edticas p\u00fablicas que permitan mejorar la calidad de la educaci\u00f3n en este \u00e1mbito, contribuyendo al fortalecimiento de las competencias de lectura y escritura de los ciudadanos chilenos, con el fin de mejorar su calidad de vida y su participaci\u00f3n en la sociedad.<\/p>\n<p style=\"font-weight: 400\">\u201cEstamos muy felices de que la UOH se haya incorporado a la red de la C\u00e1tedra Unesco porque ha estado conformando un s\u00f3lido equipo de investigaci\u00f3n en los \u00e1mbitos de escritura y lectura, teniendo un fuerte compromiso con el desarrollo docente y con el compromiso social. En ese sentido, es un gran valor poder tener la capacidad de trabajar y proyectar nuevas acciones hacia el futuro\u201d, indic\u00f3 Ren\u00e9 Venegas, director de la iniciativa en Chile, la que est\u00e1 compuesta por universidades en todo el pa\u00eds.<\/p>\n<p style=\"font-weight: 400\">Sobre el Congreso realizado en el Campus Rancagua de la Universidad de O\u2019Higgins, Ren\u00e9 Venegas se\u00f1al\u00f3 que \u201ceste tipo de actividades hablan de temas tan transversales como la introducci\u00f3n del ChatGPT y la alfabetizaci\u00f3n en nuestro sistema escolar. Es importante que se tomen distintos temas en este tipo de congresos. La escritura en s\u00ed misma es una tecnolog\u00eda y como tal hay que entender que todas las tecnolog\u00edas que nos ayuden a comunicarnos mejor siempre ser\u00e1n bienvenidas en la medida en que las usemos responsablemente y c\u00f3mo nos permiten construir conocimientos. En circunstancias, los\/as profesores\/as tenemos algunos temores de c\u00f3mo va a impactar en nuestro proceso de aprendizaje y de c\u00f3mo tenemos que adaptarnos a esta nueva tecnolog\u00eda, pero siempre que se produce una inserci\u00f3n de una nueva tecnolog\u00eda en la sociedad hay todo un proceso de crisis y esos procesos de crisis traen nuevos aprendizajes y nuevas habilidades a desarrollar en la juventud\u201d.<\/p>\n<p>[\/vc_column_text][vc_zigzag color=&#8221;white&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image image=&#8221;22126&#8243; img_size=&#8221;large&#8221; alignment=&#8221;center&#8221; onclick=&#8221;img_link_large&#8221; img_link_target=&#8221;_blank&#8221;][vc_zigzag color=&#8221;white&#8221;][vc_single_image image=&#8221;22127&#8243; img_size=&#8221;large&#8221; alignment=&#8221;center&#8221; onclick=&#8221;img_link_large&#8221; img_link_target=&#8221;_blank&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center\"><em>Ren\u00e9 Venegas.<\/em><\/p>\n<p style=\"text-align: center\"><b><i>C\u00e1tedra Unesco para el mejoramiento de la lectura y la escritura.<\/i><\/b><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650255686594{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center p-md-0 pt-5 pb-5&#8243;][vc_column el_class=&#8221;pb-5&#8243;][vc_row_inner el_class=&#8221;pb-5&#8243;][vc_column_inner]<div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0\"><h2 class=\"title title--decorator title--ms d-inline-block\">Te Recomendamos<\/h2><\/div><\/div><div class=\"content-holder\"><div class=\"row  swipper-news-list not--activate-hack \"><div class=\"row -wrapper\"><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/category\/educacion\/\">\n                                        Educaci\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2026\/05\/Laboratorio-Ensenanza-de-Matematica-4.jpg\" alt=\"Carrera de Pedagog\u00eda en Matem\u00e1tica avanza en diagn\u00f3stico sobre desarrollo de la habilidad de modelizaci\u00f3n\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/994;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Mi\u00e9rcoles 13, Mayo<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/13\/carrera-de-pedagogia-en-matematica-avanza-en-diagnostico-sobre-desarrollo-de-la-habilidad-de-modelizacion\/\">\n                                    <h3 class=\"small-space\">Carrera de Pedagog\u00eda en Matem\u00e1tica avanza en diagn\u00f3stico sobre desarrollo de la habilidad de modelizaci\u00f3n<\/h3><\/a>\n\n                                    <p>El instrumento fue aplicado a m\u00e1s de 100 estudiantes en el marco de proyectos de fortalecimiento institucional e innovaci\u00f3n docente. <\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/13\/carrera-de-pedagogia-en-matematica-avanza-en-diagnostico-sobre-desarrollo-de-la-habilidad-de-modelizacion\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/category\/educacion\/\">\n                                        Educaci\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2026\/05\/Docente-de-la-Escuela-de-Educacion-UOH-realizo-intercambio-academico-sobre-alfabetizacion-inicial-en-Brasil.png\" alt=\"Docente de la Escuela de Educaci\u00f3n UOH realiz\u00f3 intercambio acad\u00e9mico sobre alfabetizaci\u00f3n inicial en Brasil\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Martes 12, Mayo<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/12\/docente-de-la-escuela-de-educacion-uoh-realizo-intercambio-academico-sobre-alfabetizacion-inicial-en-brasil\/\">\n                                    <h3 class=\"small-space\">Docente de la Escuela de Educaci\u00f3n UOH realiz\u00f3 intercambio acad\u00e9mico sobre alfabetizaci\u00f3n inicial en Brasil<\/h3><\/a>\n\n                                    <p>Ana Ram\u00edrez particip\u00f3 en encuentros, talleres y conferencias orientadas al intercambio de experiencias sobre ense\u00f1anza de la lectura y escritura inicial en contextos latinoamericano en la Universidad de Bras\u00edlia.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/12\/docente-de-la-escuela-de-educacion-uoh-realizo-intercambio-academico-sobre-alfabetizacion-inicial-en-brasil\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/category\/educacion\/\">\n                                        Educaci\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2026\/05\/Una-jornada-marcada-por-el-deporte-la-participacion-familiar-y-el-compromiso-comunitario-se-vivio-en-el-Estadio-El-Teniente-donde-estudiantes-en-practica-profesional-de-la-Escuela-de-Educacion-d.png\" alt=\"Escuela de Educaci\u00f3n UOH particip\u00f3 en primera corrida familiar del Aula Hospitalaria de Rancagua\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Martes 5, Mayo<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/05\/escuela-de-educacion-uoh-participo-en-primera-corrida-familiar-del-aula-hospitalaria-de-rancagua\/\">\n                                    <h3 class=\"small-space\">Escuela de Educaci\u00f3n UOH particip\u00f3 en primera corrida familiar del Aula Hospitalaria de Rancagua<\/h3><\/a>\n\n                                    <p>La iniciativa desarrollada en el Estadio El Teniente promovi\u00f3 la vida saludable y fortaleci\u00f3 el v\u00ednculo entre formaci\u00f3n pedag\u00f3gica y comunidad. <\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/05\/escuela-de-educacion-uoh-participo-en-primera-corrida-familiar-del-aula-hospitalaria-de-rancagua\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pagination justify-content-center my-5\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/posts\/2247\/\/page\/2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/posts\/2247\/\/page\/3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/posts\/2247\/\/page\/156\">156<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/posts\/2247\/\/page\/2\"><div class=\"icon-pagination-next\"> <?xml version=\"1.0\" ?><svg viewBox=\"0 0 96 96\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><title\/><path d=\"M39.3756,48.0022l30.47-25.39a6.0035,6.0035,0,0,0-7.6878-9.223L26.1563,43.3906a6.0092,6.0092,0,0,0,0,9.2231L62.1578,82.615a6.0035,6.0035,0,0,0,7.6878-9.2231Z\"\/><\/svg> <\/div><\/a><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>El acuerdo tiene como objetivo principal promover la alfabetizaci\u00f3n y el desarrollo de habilidades de lectura y escritura en la poblaci\u00f3n chilena, especialmente en aquellos grupos m\u00e1s vulnerables.<\/p>\n","protected":false},"author":34,"featured_media":2248,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[25],"tags":[],"class_list":["post-2247","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>UOH y compromiso con la educaci\u00f3n: casa de estudios refuerza v\u00ednculo con C\u00e1tedra Unesco para el mejoramiento de la lectura y la escritura - Escuela de Educaci\u00f3n<\/title>\n<meta name=\"description\" content=\"El acuerdo tiene como objetivo principal promover la alfabetizaci\u00f3n y el desarrollo de habilidades de lectura y escritura en la poblaci\u00f3n chilena, especialmente en aquellos grupos m\u00e1s vulnerables.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UOH y compromiso con la educaci\u00f3n: casa de estudios refuerza v\u00ednculo con C\u00e1tedra Unesco para el mejoramiento de la lectura y la escritura - Escuela de Educaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"El acuerdo tiene como objetivo principal promover la alfabetizaci\u00f3n y el desarrollo de habilidades de lectura y escritura en la poblaci\u00f3n chilena, especialmente en aquellos grupos m\u00e1s vulnerables.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2023\/08\/30\/uoh-y-compromiso-con-la-educacion-casa-de-estudios-refuerza-vinculo-con-catedra-unesco-para-el-mejoramiento-de-la-lectura-y-la-escritura\/\" \/>\n<meta property=\"og:site_name\" content=\"Escuela de Educaci\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-30T18:47:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2023\/08\/Congreso-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Universidad de O&#039;Higgins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Universidad de O&#039;Higgins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2023\/08\/30\/uoh-y-compromiso-con-la-educacion-casa-de-estudios-refuerza-vinculo-con-catedra-unesco-para-el-mejoramiento-de-la-lectura-y-la-escritura\/\",\"url\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2023\/08\/30\/uoh-y-compromiso-con-la-educacion-casa-de-estudios-refuerza-vinculo-con-catedra-unesco-para-el-mejoramiento-de-la-lectura-y-la-escritura\/\",\"name\":\"UOH y compromiso con la educaci\u00f3n: casa de estudios refuerza v\u00ednculo con C\u00e1tedra Unesco para el mejoramiento de la lectura y la escritura - Escuela de Educaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2023\/08\/30\/uoh-y-compromiso-con-la-educacion-casa-de-estudios-refuerza-vinculo-con-catedra-unesco-para-el-mejoramiento-de-la-lectura-y-la-escritura\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2023\/08\/30\/uoh-y-compromiso-con-la-educacion-casa-de-estudios-refuerza-vinculo-con-catedra-unesco-para-el-mejoramiento-de-la-lectura-y-la-escritura\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2023\/08\/Congreso-2.png\",\"datePublished\":\"2023-08-30T18:47:08+00:00\",\"author\":{\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"description\":\"El acuerdo tiene como objetivo principal promover la alfabetizaci\u00f3n y el desarrollo de habilidades de lectura y escritura en la poblaci\u00f3n chilena, especialmente en aquellos grupos m\u00e1s vulnerables.\",\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2023\/08\/30\/uoh-y-compromiso-con-la-educacion-casa-de-estudios-refuerza-vinculo-con-catedra-unesco-para-el-mejoramiento-de-la-lectura-y-la-escritura\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2023\/08\/30\/uoh-y-compromiso-con-la-educacion-casa-de-estudios-refuerza-vinculo-con-catedra-unesco-para-el-mejoramiento-de-la-lectura-y-la-escritura\/#primaryimage\",\"url\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2023\/08\/Congreso-2.png\",\"contentUrl\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2023\/08\/Congreso-2.png\",\"width\":1000,\"height\":1000},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/#website\",\"url\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/\",\"name\":\"Escuela de Educaci\u00f3n\",\"description\":\"Otro sitio de Sitios de Universidad O'higgins\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\",\"name\":\"Universidad de O'Higgins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"caption\":\"Universidad de O'Higgins\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UOH y compromiso con la educaci\u00f3n: casa de estudios refuerza v\u00ednculo con C\u00e1tedra Unesco para el mejoramiento de la lectura y la escritura - Escuela de Educaci\u00f3n","description":"El acuerdo tiene como objetivo principal promover la alfabetizaci\u00f3n y el desarrollo de habilidades de lectura y escritura en la poblaci\u00f3n chilena, especialmente en aquellos grupos m\u00e1s vulnerables.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"UOH y compromiso con la educaci\u00f3n: casa de estudios refuerza v\u00ednculo con C\u00e1tedra Unesco para el mejoramiento de la lectura y la escritura - Escuela de Educaci\u00f3n","og_description":"El acuerdo tiene como objetivo principal promover la alfabetizaci\u00f3n y el desarrollo de habilidades de lectura y escritura en la poblaci\u00f3n chilena, especialmente en aquellos grupos m\u00e1s vulnerables.","og_url":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2023\/08\/30\/uoh-y-compromiso-con-la-educacion-casa-de-estudios-refuerza-vinculo-con-catedra-unesco-para-el-mejoramiento-de-la-lectura-y-la-escritura\/","og_site_name":"Escuela de Educaci\u00f3n","article_published_time":"2023-08-30T18:47:08+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2023\/08\/Congreso-2.png","type":"image\/png"}],"author":"Universidad de O'Higgins","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Universidad de O'Higgins","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2023\/08\/30\/uoh-y-compromiso-con-la-educacion-casa-de-estudios-refuerza-vinculo-con-catedra-unesco-para-el-mejoramiento-de-la-lectura-y-la-escritura\/","url":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2023\/08\/30\/uoh-y-compromiso-con-la-educacion-casa-de-estudios-refuerza-vinculo-con-catedra-unesco-para-el-mejoramiento-de-la-lectura-y-la-escritura\/","name":"UOH y compromiso con la educaci\u00f3n: casa de estudios refuerza v\u00ednculo con C\u00e1tedra Unesco para el mejoramiento de la lectura y la escritura - Escuela de Educaci\u00f3n","isPartOf":{"@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2023\/08\/30\/uoh-y-compromiso-con-la-educacion-casa-de-estudios-refuerza-vinculo-con-catedra-unesco-para-el-mejoramiento-de-la-lectura-y-la-escritura\/#primaryimage"},"image":{"@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2023\/08\/30\/uoh-y-compromiso-con-la-educacion-casa-de-estudios-refuerza-vinculo-con-catedra-unesco-para-el-mejoramiento-de-la-lectura-y-la-escritura\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2023\/08\/Congreso-2.png","datePublished":"2023-08-30T18:47:08+00:00","author":{"@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"description":"El acuerdo tiene como objetivo principal promover la alfabetizaci\u00f3n y el desarrollo de habilidades de lectura y escritura en la poblaci\u00f3n chilena, especialmente en aquellos grupos m\u00e1s vulnerables.","inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/escuela-de-educacion\/2023\/08\/30\/uoh-y-compromiso-con-la-educacion-casa-de-estudios-refuerza-vinculo-con-catedra-unesco-para-el-mejoramiento-de-la-lectura-y-la-escritura\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2023\/08\/30\/uoh-y-compromiso-con-la-educacion-casa-de-estudios-refuerza-vinculo-con-catedra-unesco-para-el-mejoramiento-de-la-lectura-y-la-escritura\/#primaryimage","url":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2023\/08\/Congreso-2.png","contentUrl":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2023\/08\/Congreso-2.png","width":1000,"height":1000},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/#website","url":"https:\/\/www.uoh.cl\/escuela-de-educacion\/","name":"Escuela de Educaci\u00f3n","description":"Otro sitio de Sitios de Universidad O'higgins","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/escuela-de-educacion\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f","name":"Universidad de O'Higgins","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","caption":"Universidad de O'Higgins"}}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/posts\/2247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/comments?post=2247"}],"version-history":[{"count":0,"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/posts\/2247\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/media\/2248"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/media?parent=2247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/categories?post=2247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/tags?post=2247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}