
{"id":1172,"date":"2022-10-27T09:35:57","date_gmt":"2022-10-27T12:35:57","guid":{"rendered":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2022\/10\/27\/taller-de-igualdad-de-genero-marca-la-jornada-en-sesion-cuech-en-valdivia\/"},"modified":"2022-10-27T09:35:57","modified_gmt":"2022-10-27T12:35:57","slug":"taller-de-igualdad-de-genero-marca-la-jornada-en-sesion-cuech-en-valdivia","status":"publish","type":"post","link":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2022\/10\/27\/taller-de-igualdad-de-genero-marca-la-jornada-en-sesion-cuech-en-valdivia\/","title":{"rendered":"Taller de Igualdad de G\u00e9nero marca la jornada en sesi\u00f3n CUECH en Valdivia"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center text-right circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row][vc_column]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\"><span itemprop=\"name\">Escuela de Educaci\u00f3n <\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/noticias\/\"><span itemprop=\"name\">Noticias<\/span><\/a><meta itemprop=\"position\" content=\"3\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Taller de Igualdad de G\u00e9nero marca la jornada en sesi\u00f3n <\/span><meta itemprop=\"position\" content=\"4\" \/><\/ol><\/div><ul class=\"p-0 list-style-none d-inline-block\"><li class=\"p-0\"><a href=https:\/\/www.uoh.cl\/escuela-de-educacion\/category\/institucional\/ class=\"px-1 py-2\">Institucional<\/a><\/li><\/ul><div class=\"date_publish_post\"> \u25cf Jue 27 de Octubre 2022<\/div><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block title--decorator  big\">Taller de Igualdad de G\u00e9nero marca la jornada en sesi\u00f3n CUECH en Valdivia<\/h1><\/div>[vc_row_inner el_class=&#8221;border-separator m-0&#8243;][vc_column_inner width=&#8221;2\/3&#8243;][\/vc_column_inner][vc_column_inner el_class=&#8221;align-items-end-publish&#8221; width=&#8221;1\/3&#8243;]<div class=\"uoh_social_network_component uoh_row col-12 justify-content-end m-0 p-0\"> <div class=\"icon__facebook-share-button\">\n                       <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.uoh.cl\/escuela-de-educacion\/2022\/10\/27\/taller-de-igualdad-de-genero-marca-la-jornada-en-sesion-cuech-en-valdivia\/\" target=\"_blank\"> <div class=\"icon__facebook-svg\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22.4px\" height=\"48.3px\" viewBox=\"0 0 22.4 48.3\" style=\"overflow:visible;enable-background:new 0 0 22.4 48.3;\" xml:space=\"preserve\">\n                <defs>\n                <\/defs>\n                <path class=\"st0\" d=\"M22.4,15.6h-7.6v-5c0-1.9,1.2-2.3,2.1-2.3c0.9,0,5.4,0,5.4,0V0l-7.4,0C6.6,0,4.8,6.2,4.8,10.1v5.5H0v8.5h4.8\n                    c0,10.9,0,24.1,0,24.1h10c0,0,0-13.3,0-24.1h6.8L22.4,15.6z\"><\/path>\n                <\/svg><\/a><\/div>\n                    <\/div><div class=\"icon__twitter-share-button\">\n                        <div class=\"icon__twitter-svg\"><a target=\"_blank\" href=\"http:\/\/twitter.com\/share?url=https:\/\/www.uoh.cl\/escuela-de-educacion\/2022\/10\/27\/taller-de-igualdad-de-genero-marca-la-jornada-en-sesion-cuech-en-valdivia\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/a><\/div>\n                        <\/div><div class=\"icon__linkedin-share-button\">\n                        <div class=\"icon__linkedin-svg\">\n                        <a target=\"__blank\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.uoh.cl\/escuela-de-educacion\/2022\/10\/27\/taller-de-igualdad-de-genero-marca-la-jornada-en-sesion-cuech-en-valdivia\/\"><svg enable-background=\"new 0 0 100 100\" height=\"100px\" id=\"Layer_1\" version=\"1.1\" viewBox=\"0 0 100 100\" width=\"100px\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><circle cx=\"50\" cy=\"50\" fill=\"#ccc\" r=\"45\"\/><g id=\"LinkedIn_1_\"><rect fill=\"#FFFFFF\" height=\"24.361\" width=\"7.69\" x=\"31.271\" y=\"43.569\"\/><path d=\"M59.968,43.334c-4.406,0-7.165,2.387-7.677,4.058v-3.823h-8.636c0.109,2.03,0,24.361,0,24.361h8.636    V54.748c0-0.733-0.034-1.465,0.19-1.991c0.594-1.464,1.869-2.985,4.162-2.985c2.998,0,4.361,2.253,4.361,5.552V67.93h8.721V54.384    C69.726,46.839,65.432,43.334,59.968,43.334z\" fill=\"#FFFFFF\"\/><path d=\"M34.973,32.069c-2.839,0-4.696,1.823-4.696,4.229c0,2.361,1.804,4.224,4.589,4.224h0.054    c2.891,0,4.69-1.869,4.69-4.229C39.555,33.888,37.81,32.069,34.973,32.069z\" fill=\"#FFFFFF\"\/><\/g><\/g><\/svg><\/a><\/div>\n\n            <\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_single_image image=&#8221;12031&#8243; img_size=&#8221;large&#8221;][vc_column_text]\u00a0[\/vc_column_text][vc_column_text]<em><span style=\"text-align: justify\">Las y los rectores de las Universidades P\u00fablicas, analizaron los alcances y desaf\u00edos de las pol\u00edticas de igualdad de g\u00e9nero desarrolladas al interior de las universidades estatales, a partir de experiencias en algunas de ellas, en el marco de su reuni\u00f3n mensual en la ciudad de Valdivia.<\/span><\/em>[\/vc_column_text]<div class=\"author_wp_class\"> Escrito por <span>Universidad de O'Higgins<\/span><\/div>[vc_column_text]\u00a0[\/vc_column_text][vc_column_text]\u201cEstamos en un trabajo amplio y hemos realizado en cada una de las 18 universidades un diagn\u00f3stico para observar las desigualdades de g\u00e9nero que se presentan\u201d menciona Ang\u00e9lica Mar\u00edn, secretaria ejecutiva de la oficina de G\u00e9nero y Sexualidades de la UMCE. La acad\u00e9mica fue una de las responsables de dictar el taller \u201cAlcances de las pol\u00edticas de igualdad de g\u00e9nero\u201d en la sesi\u00f3n de octubre de las y los rectores que componen el Consorcio de Universidades del Estado (CUECH).<\/p>\n<p>El taller fue dictado por las acad\u00e9micas Antonia Santos (U. Chile), Carmen Andrea (U. Chile), Ang\u00e9lica Mar\u00edn (UMCE) y Rosario Garc\u00eda Huidobro (U. de Los Lagos) y se enmarca en el trabajo que las Universidades del Estado, articuladas desde el CUECH, realizan para combatir las desigualdades y avanzar hacia un trabajo con mirada de g\u00e9nero de forma integral e interseccional.<\/p>\n<p>Sobre el trabajo universitario en ese sentido, el presidente del CUECH\u00a0 y rector de la Universidad de Valpara\u00edso Osvaldo Corrales se\u00f1ala que \u201clas Universidades Estatales estamos comprometidas con la eliminaci\u00f3n de toda forma de violencia y de discriminaci\u00f3n al interior de nuestras instituciones, y, precisamente para avanzar en ese prop\u00f3sito com\u00fan, estamos realizando un taller en el que estamos compartiendo un diagn\u00f3stico que se ha hecho en el marco del trabajo en red que las Universidades del Estado desarrollamos permanentemente\u201d.<\/p>\n<p>Corrales indica que los planteles p\u00fablicos est\u00e1n haciendo un trabajo intencionado y dirigido, y que, si bien esa labor tiene una base en la Ley 21.369, los objetivos propuestos van m\u00e1s all\u00e1 de los l\u00edmites legales: \u201cLas instituciones del Estado no esperamos que hubiera una ley, la mayor\u00eda de nuestras instituciones vienen trabajando al menos desde 2014 o 2015 y por supuesto, con mucho m\u00e1s \u00e9nfasis despu\u00e9s del 2018\u201d.<\/p>\n<p>Sin embargo, el rector enfatiza que las pol\u00edticas p\u00fablicas en estas materias deber\u00edan considerar aportes financieros para una adecuada implementaci\u00f3n de las mayores exigencias que implican: \u201cFalta el compromiso de involucrar, por parte de la pol\u00edtica p\u00fablica, recursos que le permitan a las instituciones que aquello que est\u00e1 incluido en cuerpos legales, pueda trasladarse a la realidad institucional\u201d.<\/p>\n<p>Con respecto al diagn\u00f3stico que realizaron las Universidades del Estado en mateira de igualdad de g\u00e9nero, Ang\u00e9lica Mar\u00edn, desde la UMCE, se\u00f1ala que \u201cse identifica que a\u00fan hay brechas de g\u00e9nero en ciertos campos disciplinares y est\u00e1n muy asociadas a la divisi\u00f3n sexual del trabajo (\u2026) Hoy, en 2022 a\u00fan persisten este tipo de segmentaciones, as\u00ed como tambi\u00e9n la menor presencia de mujeres en campos directivos. Se ve que hay avances, pero aun as\u00ed se visualiza que hay todav\u00eda amplio margen de mejora para ir incorporando esa mirada paritaria\u201d.<\/p>\n<p>La sesi\u00f3n fue la primera para Luperfina Rojas como rectora electa de la U. de La Serena, as\u00ed como para Carlos Gonz\u00e1lez nuevo rector de la Universidad de Playa Ancha, \u00a0e incorpor\u00f3 tambi\u00e9n an\u00e1lisis referidos a la discusi\u00f3n presupuestaria, escenario complejo para las Universidades Estatales que enfrentan un deterioro en sus indicadores financieros desde el inicio de la pandemia, debido a la menor matr\u00edcula y a las inversiones extraordinarias que implic\u00f3 la situaci\u00f3n acad\u00e9mica y estudiantil durante el 2020 y 2021. El llamado de los planteles p\u00fablicos es a permitir el uso de excedentes acumulados del Fondo Solidario, el otorgamiento de la garant\u00eda del Estado para el endeudamiento de largo plazo y a priorizar la educaci\u00f3n p\u00fablica como valor esencial en el desarrollo del pa\u00eds.<\/p>\n<p>Corrales concluye que \u201cnecesitamos tener pol\u00edticas que promuevan la igualdad efectiva de g\u00e9nero y que pasemos de una pol\u00edtica de g\u00e9nero a una perspectiva de g\u00e9nero que se traduzca en cambios en el curr\u00edculum, cambios en la carrera acad\u00e9mica, en la forma en la que conceptualizamos la investigaci\u00f3n y la vinculaci\u00f3n con el medio.\u00a0 El 100% de las universidades ya tenemos pol\u00edticas destinadas a sancionar conductas que buscamos erradicar como el acoso sexual o la violencia, pero hoy el desaf\u00edo es ese cambio cultural\u201d.<\/p>\n<p>La pr\u00f3xima sesi\u00f3n de rectoras\/es se proyecta para fines de noviembre en Ays\u00e9n. M\u00e1s informaci\u00f3n sobre el sistema p\u00fablico de Universidades y sus proyectos en red est\u00e1 disponible en <a href=\"http:\/\/uestatales.cl\">http:\/\/uestatales.cl<\/a><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650255686594{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center text-right p-md-0 pt-5 pb-5&#8243;][vc_column el_class=&#8221;pb-5&#8243;][vc_row_inner el_class=&#8221;pb-5&#8243;][vc_column_inner]<div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0\"><h2 class=\"title title--decorator title--ms d-inline-block\">Te Recomendamos<\/h2><\/div><\/div><div class=\"content-holder\"><div class=\"row  swipper-news-list not--activate-hack \"><div class=\"row -wrapper\"><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/category\/educacion\/\">\n                                        Educaci\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2026\/05\/Laboratorio-Ensenanza-de-Matematica-4.jpg\" alt=\"Carrera de Pedagog\u00eda en Matem\u00e1tica avanza en diagn\u00f3stico sobre desarrollo de la habilidad de modelizaci\u00f3n\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/994;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Mi\u00e9rcoles 13, Mayo<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/13\/carrera-de-pedagogia-en-matematica-avanza-en-diagnostico-sobre-desarrollo-de-la-habilidad-de-modelizacion\/\">\n                                    <h3 class=\"small-space\">Carrera de Pedagog\u00eda en Matem\u00e1tica avanza en diagn\u00f3stico sobre desarrollo de la habilidad de modelizaci\u00f3n<\/h3><\/a>\n\n                                    <p>El instrumento fue aplicado a m\u00e1s de 100 estudiantes en el marco de proyectos de fortalecimiento institucional e innovaci\u00f3n docente. <\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/13\/carrera-de-pedagogia-en-matematica-avanza-en-diagnostico-sobre-desarrollo-de-la-habilidad-de-modelizacion\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/category\/educacion\/\">\n                                        Educaci\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2026\/05\/Docente-de-la-Escuela-de-Educacion-UOH-realizo-intercambio-academico-sobre-alfabetizacion-inicial-en-Brasil.png\" alt=\"Docente de la Escuela de Educaci\u00f3n UOH realiz\u00f3 intercambio acad\u00e9mico sobre alfabetizaci\u00f3n inicial en Brasil\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Martes 12, Mayo<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/12\/docente-de-la-escuela-de-educacion-uoh-realizo-intercambio-academico-sobre-alfabetizacion-inicial-en-brasil\/\">\n                                    <h3 class=\"small-space\">Docente de la Escuela de Educaci\u00f3n UOH realiz\u00f3 intercambio acad\u00e9mico sobre alfabetizaci\u00f3n inicial en Brasil<\/h3><\/a>\n\n                                    <p>Ana Ram\u00edrez particip\u00f3 en encuentros, talleres y conferencias orientadas al intercambio de experiencias sobre ense\u00f1anza de la lectura y escritura inicial en contextos latinoamericano en la Universidad de Bras\u00edlia.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/12\/docente-de-la-escuela-de-educacion-uoh-realizo-intercambio-academico-sobre-alfabetizacion-inicial-en-brasil\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/category\/educacion\/\">\n                                        Educaci\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2026\/05\/Una-jornada-marcada-por-el-deporte-la-participacion-familiar-y-el-compromiso-comunitario-se-vivio-en-el-Estadio-El-Teniente-donde-estudiantes-en-practica-profesional-de-la-Escuela-de-Educacion-d.png\" alt=\"Escuela de Educaci\u00f3n UOH particip\u00f3 en primera corrida familiar del Aula Hospitalaria de Rancagua\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Martes 5, Mayo<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/05\/escuela-de-educacion-uoh-participo-en-primera-corrida-familiar-del-aula-hospitalaria-de-rancagua\/\">\n                                    <h3 class=\"small-space\">Escuela de Educaci\u00f3n UOH particip\u00f3 en primera corrida familiar del Aula Hospitalaria de Rancagua<\/h3><\/a>\n\n                                    <p>La iniciativa desarrollada en el Estadio El Teniente promovi\u00f3 la vida saludable y fortaleci\u00f3 el v\u00ednculo entre formaci\u00f3n pedag\u00f3gica y comunidad. <\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2026\/05\/05\/escuela-de-educacion-uoh-participo-en-primera-corrida-familiar-del-aula-hospitalaria-de-rancagua\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pagination justify-content-center my-5\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/posts\/1172\/\/page\/2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/posts\/1172\/\/page\/3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/posts\/1172\/\/page\/156\">156<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/posts\/1172\/\/page\/2\"><div class=\"icon-pagination-next\"> <?xml version=\"1.0\" ?><svg viewBox=\"0 0 96 96\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><title\/><path d=\"M39.3756,48.0022l30.47-25.39a6.0035,6.0035,0,0,0-7.6878-9.223L26.1563,43.3906a6.0092,6.0092,0,0,0,0,9.2231L62.1578,82.615a6.0035,6.0035,0,0,0,7.6878-9.2231Z\"\/><\/svg> <\/div><\/a><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Las y los rectores de las Universidades P\u00fablicas, analizaron los alcances y desaf\u00edos de las pol\u00edticas de igualdad de g\u00e9nero desarrolladas al interior de las universidades estatales, a partir de experiencias en algunas de ellas, en el marco de su reuni\u00f3n mensual en la ciudad de Valdivia.<\/p>\n","protected":false},"author":34,"featured_media":1173,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-1172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucional"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Taller de Igualdad de G\u00e9nero marca la jornada en sesi\u00f3n CUECH en Valdivia - Escuela de Educaci\u00f3n<\/title>\n<meta name=\"description\" content=\"Las y los rectores de las Universidades P\u00fablicas, analizaron los alcances y desaf\u00edos de las pol\u00edticas de igualdad de g\u00e9nero desarrolladas al interior de las universidades estatales, a partir de experiencias en algunas de ellas, en el marco de su reuni\u00f3n mensual en la ciudad de Valdivia.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Taller de Igualdad de G\u00e9nero marca la jornada en sesi\u00f3n CUECH en Valdivia - Escuela de Educaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Las y los rectores de las Universidades P\u00fablicas, analizaron los alcances y desaf\u00edos de las pol\u00edticas de igualdad de g\u00e9nero desarrolladas al interior de las universidades estatales, a partir de experiencias en algunas de ellas, en el marco de su reuni\u00f3n mensual en la ciudad de Valdivia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2022\/10\/27\/taller-de-igualdad-de-genero-marca-la-jornada-en-sesion-cuech-en-valdivia\/\" \/>\n<meta property=\"og:site_name\" content=\"Escuela de Educaci\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-27T12:35:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2022\/10\/CUECH.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Universidad de O&#039;Higgins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Universidad de O&#039;Higgins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2022\/10\/27\/taller-de-igualdad-de-genero-marca-la-jornada-en-sesion-cuech-en-valdivia\/\",\"url\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2022\/10\/27\/taller-de-igualdad-de-genero-marca-la-jornada-en-sesion-cuech-en-valdivia\/\",\"name\":\"Taller de Igualdad de G\u00e9nero marca la jornada en sesi\u00f3n CUECH en Valdivia - Escuela de Educaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2022\/10\/27\/taller-de-igualdad-de-genero-marca-la-jornada-en-sesion-cuech-en-valdivia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2022\/10\/27\/taller-de-igualdad-de-genero-marca-la-jornada-en-sesion-cuech-en-valdivia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2022\/10\/CUECH.jpg\",\"datePublished\":\"2022-10-27T12:35:57+00:00\",\"author\":{\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"description\":\"Las y los rectores de las Universidades P\u00fablicas, analizaron los alcances y desaf\u00edos de las pol\u00edticas de igualdad de g\u00e9nero desarrolladas al interior de las universidades estatales, a partir de experiencias en algunas de ellas, en el marco de su reuni\u00f3n mensual en la ciudad de Valdivia.\",\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2022\/10\/27\/taller-de-igualdad-de-genero-marca-la-jornada-en-sesion-cuech-en-valdivia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/2022\/10\/27\/taller-de-igualdad-de-genero-marca-la-jornada-en-sesion-cuech-en-valdivia\/#primaryimage\",\"url\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2022\/10\/CUECH.jpg\",\"contentUrl\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2022\/10\/CUECH.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/#website\",\"url\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/\",\"name\":\"Escuela de Educaci\u00f3n\",\"description\":\"Otro sitio de Sitios de Universidad O'higgins\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\",\"name\":\"Universidad de O'Higgins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-educacion\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"caption\":\"Universidad de O'Higgins\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Taller de Igualdad de G\u00e9nero marca la jornada en sesi\u00f3n CUECH en Valdivia - Escuela de Educaci\u00f3n","description":"Las y los rectores de las Universidades P\u00fablicas, analizaron los alcances y desaf\u00edos de las pol\u00edticas de igualdad de g\u00e9nero desarrolladas al interior de las universidades estatales, a partir de experiencias en algunas de ellas, en el marco de su reuni\u00f3n mensual en la ciudad de Valdivia.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Taller de Igualdad de G\u00e9nero marca la jornada en sesi\u00f3n CUECH en Valdivia - Escuela de Educaci\u00f3n","og_description":"Las y los rectores de las Universidades P\u00fablicas, analizaron los alcances y desaf\u00edos de las pol\u00edticas de igualdad de g\u00e9nero desarrolladas al interior de las universidades estatales, a partir de experiencias en algunas de ellas, en el marco de su reuni\u00f3n mensual en la ciudad de Valdivia.","og_url":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2022\/10\/27\/taller-de-igualdad-de-genero-marca-la-jornada-en-sesion-cuech-en-valdivia\/","og_site_name":"Escuela de Educaci\u00f3n","article_published_time":"2022-10-27T12:35:57+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2022\/10\/CUECH.jpg","type":"image\/jpeg"}],"author":"Universidad de O'Higgins","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Universidad de O'Higgins","Tiempo estimado de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2022\/10\/27\/taller-de-igualdad-de-genero-marca-la-jornada-en-sesion-cuech-en-valdivia\/","url":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2022\/10\/27\/taller-de-igualdad-de-genero-marca-la-jornada-en-sesion-cuech-en-valdivia\/","name":"Taller de Igualdad de G\u00e9nero marca la jornada en sesi\u00f3n CUECH en Valdivia - Escuela de Educaci\u00f3n","isPartOf":{"@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2022\/10\/27\/taller-de-igualdad-de-genero-marca-la-jornada-en-sesion-cuech-en-valdivia\/#primaryimage"},"image":{"@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2022\/10\/27\/taller-de-igualdad-de-genero-marca-la-jornada-en-sesion-cuech-en-valdivia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2022\/10\/CUECH.jpg","datePublished":"2022-10-27T12:35:57+00:00","author":{"@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"description":"Las y los rectores de las Universidades P\u00fablicas, analizaron los alcances y desaf\u00edos de las pol\u00edticas de igualdad de g\u00e9nero desarrolladas al interior de las universidades estatales, a partir de experiencias en algunas de ellas, en el marco de su reuni\u00f3n mensual en la ciudad de Valdivia.","inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/escuela-de-educacion\/2022\/10\/27\/taller-de-igualdad-de-genero-marca-la-jornada-en-sesion-cuech-en-valdivia\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/2022\/10\/27\/taller-de-igualdad-de-genero-marca-la-jornada-en-sesion-cuech-en-valdivia\/#primaryimage","url":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2022\/10\/CUECH.jpg","contentUrl":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-content\/uploads\/sites\/17\/2022\/10\/CUECH.jpg","width":1000,"height":1000},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/#website","url":"https:\/\/www.uoh.cl\/escuela-de-educacion\/","name":"Escuela de Educaci\u00f3n","description":"Otro sitio de Sitios de Universidad O'higgins","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/escuela-de-educacion\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f","name":"Universidad de O'Higgins","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/escuela-de-educacion\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","caption":"Universidad de O'Higgins"}}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/posts\/1172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/comments?post=1172"}],"version-history":[{"count":0,"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/posts\/1172\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/media\/1173"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/media?parent=1172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/categories?post=1172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-educacion\/wp-json\/wp\/v2\/tags?post=1172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}