
{"id":2470,"date":"2024-07-24T15:12:08","date_gmt":"2024-07-24T18:12:08","guid":{"rendered":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/escuela-de-ciencias-sociales-titulo-a-82-egresadas-os-de-tres-carreras\/"},"modified":"2024-07-24T17:12:07","modified_gmt":"2024-07-24T20:12:07","slug":"escuela-de-ciencias-sociales-titulo-a-82-egresadas-os-de-tres-carreras","status":"publish","type":"post","link":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/escuela-de-ciencias-sociales-titulo-a-82-egresadas-os-de-tres-carreras\/","title":{"rendered":"Escuela de Ciencias Sociales titul\u00f3 a 82 egresadas\/os de tres carreras"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row][vc_column]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\"><span itemprop=\"name\">Escuela de Ciencias de Sociales<\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/noticias\/\"><span itemprop=\"name\">Noticias<\/span><\/a><meta itemprop=\"position\" content=\"3\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Escuela de Ciencias Sociales titul\u00f3 a 82 egresadas\/os de tres <\/span><meta itemprop=\"position\" content=\"4\" \/><\/ol><\/div><ul class=\"p-0 list-style-none d-inline-block\"><li class=\"p-0\"><a href=https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/category\/ciencias-sociales\/ class=\"px-1 py-2\">Ciencias Sociales<\/a><\/li><\/ul><div class=\"date_publish_post\"> \u25cf Mi\u00e9 24 de Julio 2024<\/div><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block title--decorator  big\">Escuela de Ciencias Sociales titul\u00f3 a 82 egresadas\/os de tres carreras<\/h1><\/div>[vc_row_inner el_class=&#8221;border-separator m-0&#8243;][vc_column_inner width=&#8221;2\/3&#8243;]<div class=\"author_wp_class\"> Escrito por <span>Universidad de O'Higgins<\/span><\/div>[\/vc_column_inner][vc_column_inner el_class=&#8221;align-items-end-publish&#8221; width=&#8221;1\/3&#8243;]<div class=\"uoh_social_network_component uoh_row col-12 justify-content-end m-0 p-0\"> <div class=\"icon__facebook-share-button\">\n                       <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/escuela-de-ciencias-sociales-titulo-a-82-egresadas-os-de-tres-carreras\/\" target=\"_blank\"> <div class=\"icon__facebook-svg\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22.4px\" height=\"48.3px\" viewBox=\"0 0 22.4 48.3\" style=\"overflow:visible;enable-background:new 0 0 22.4 48.3;\" xml:space=\"preserve\">\n                <defs>\n                <\/defs>\n                <path class=\"st0\" d=\"M22.4,15.6h-7.6v-5c0-1.9,1.2-2.3,2.1-2.3c0.9,0,5.4,0,5.4,0V0l-7.4,0C6.6,0,4.8,6.2,4.8,10.1v5.5H0v8.5h4.8\n                    c0,10.9,0,24.1,0,24.1h10c0,0,0-13.3,0-24.1h6.8L22.4,15.6z\"><\/path>\n                <\/svg><\/a><\/div>\n                    <\/div><div class=\"icon__twitter-share-button\">\n                        <div class=\"icon__twitter-svg\"><a target=\"_blank\" href=\"http:\/\/twitter.com\/share?url=https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/escuela-de-ciencias-sociales-titulo-a-82-egresadas-os-de-tres-carreras\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/a><\/div>\n                        <\/div><div class=\"icon__linkedin-share-button\">\n                        <div class=\"icon__linkedin-svg\">\n                        <a target=\"__blank\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/escuela-de-ciencias-sociales-titulo-a-82-egresadas-os-de-tres-carreras\/\"><svg enable-background=\"new 0 0 100 100\" height=\"100px\" id=\"Layer_1\" version=\"1.1\" viewBox=\"0 0 100 100\" width=\"100px\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><circle cx=\"50\" cy=\"50\" fill=\"#ccc\" r=\"45\"\/><g id=\"LinkedIn_1_\"><rect fill=\"#FFFFFF\" height=\"24.361\" width=\"7.69\" x=\"31.271\" y=\"43.569\"\/><path d=\"M59.968,43.334c-4.406,0-7.165,2.387-7.677,4.058v-3.823h-8.636c0.109,2.03,0,24.361,0,24.361h8.636    V54.748c0-0.733-0.034-1.465,0.19-1.991c0.594-1.464,1.869-2.985,4.162-2.985c2.998,0,4.361,2.253,4.361,5.552V67.93h8.721V54.384    C69.726,46.839,65.432,43.334,59.968,43.334z\" fill=\"#FFFFFF\"\/><path d=\"M34.973,32.069c-2.839,0-4.696,1.823-4.696,4.229c0,2.361,1.804,4.224,4.589,4.224h0.054    c2.891,0,4.69-1.869,4.69-4.229C39.555,33.888,37.81,32.069,34.973,32.069z\" fill=\"#FFFFFF\"\/><\/g><\/g><\/svg><\/a><\/div>\n\n            <\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_single_image image=&#8221;35862&#8243; img_size=&#8221;full&#8221; add_caption=&#8221;yes&#8221; alignment=&#8221;center&#8221; onclick=&#8221;img_link_large&#8221; img_link_target=&#8221;_blank&#8221; css=&#8221;&#8221;][vc_column_text]\u00a0[\/vc_column_text][vc_column_text css=&#8221;&#8221;]<\/p>\n<ul>\n<li><em>La regi\u00f3n cuenta con nuevas\/os profesionales en las \u00e1reas de Administraci\u00f3n P\u00fablica, Psicolog\u00eda e Ingenier\u00eda Comercial.<\/em><\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_column_text]\u00a0[\/vc_column_text][vc_column_text css=&#8221;&#8221;]En su segundo a\u00f1o de ceremonias de titulaci\u00f3n, la Escuela de Ciencias Sociales de la Universidad de O\u2019Higgins celebr\u00f3 un importante hito al entregar diplomas a 82 egresadas y egresados. Estos nuevos profesionales culminaron con \u00e9xito su plan de estudios, preparados para enfrentar los desaf\u00edos de sus respectivas disciplinas. Las carreras que formaron parte de esta generaci\u00f3n de graduados incluyen Psicolog\u00eda, Administraci\u00f3n P\u00fablica e Ingenier\u00eda Comercial.<\/p>\n<p>La ceremonia fue presidida por el Vicerrector Acad\u00e9mico, Carlos P\u00e9rez Wilson, y cont\u00f3 con la presencia del director de la Escuela de Ciencias Sociales, \u00c1lvaro Astudillo. Adem\u00e1s, asistieron diversas autoridades universitarias, los jefes de las carreras de la escuela, acad\u00e9micos, docentes, as\u00ed como familiares y amigos de las y los nuevos profesionales.<\/p>\n<p>Este evento no solo marca el cierre de una etapa educativa, sino tambi\u00e9n el comienzo de una prometedora carrera para cada una\/o de las\/os tituladas\/os. La emotividad y el orgullo se reflejaron en los rostros de los asistentes, quienes compartieron momentos de alegr\u00eda y celebraci\u00f3n, reafirmando el compromiso de la universidad con la formaci\u00f3n integral y de calidad de sus estudiantes.<\/p>\n<p>&#8220;Nuestros esfuerzos, durante este periodo de formaci\u00f3n, han apuntado a preparar a estos profesionales para ser personas cr\u00edticas, pero a la vez \u00a0constructivas, al enfrentar la realidad que les espera. La etapa de formaci\u00f3n ha concluido, y ahora deben comenzar su ejercicio profesional. Esperamos que las herramientas adquiridas, en su paso por la Universidad, les sean de gran utilidad para generar los cambios necesarios que tanto la regi\u00f3n como el pa\u00eds requieren&#8221;, apunt\u00f3 el director de la Escuela de Ciencias Sociales, \u00c1lvaro Astudillo.<\/p>\n<h4><strong>Nuevas\/os profesionales<\/strong><\/h4>\n<p>Para Ram\u00f3n Herrera, titulado de la carrera de Ingenier\u00eda Comercial, &#8220;este es un momento de profundo orgullo, por haber alcanzado este logro, seguido de una inevitable nostalgia al ver la universidad y saber que este ciclo ha concluido. La universidad tiene una visi\u00f3n \u00fanica con su enfoque regional, lo cual genera un impacto positivo. Mi mayor desaf\u00edo es reconocer como, a trav\u00e9s de mi \u00e1rea, puedo impulsar el desarrollo de la regi\u00f3n y contribuir de la mejor manera posible para que este territorio siga creciendo. Adem\u00e1s, es fundamental trabajar hacia la descentralizaci\u00f3n del pa\u00eds&#8221;.<\/p>\n<p>En tanto, Zulema Celis se\u00f1al\u00f3 que \u201cquiero seguir trabajando en mi regi\u00f3n y contribuir a mi comunidad, especialmente siendo de una comuna como Codegua. Afortunadamente, la universidad nos ha brindado una formaci\u00f3n integral en diversas \u00e1reas, por lo que me siento preparada y entusiasta por aportar en todos los \u00e1mbitos de la administraci\u00f3n p\u00fablica y las ciencias sociales\u201d.<\/p>\n<p>Finalmente, Yussin Aqueveque apunt\u00f3 que \u201ca todas\/os las\/os interesadas\/os en la psicolog\u00eda y que est\u00e9n considerando estudiar en la UOH, les digo: atr\u00e9vanse. La psicolog\u00eda es una carrera hermosa y fascinante. Si sienten pasi\u00f3n por entender y ayudar a las personas, ser\u00e1n muy felices estudi\u00e1ndola. El contacto humano y la capacidad de hacer una diferencia en la vida de otros es realmente gratificante\u201d.[\/vc_column_text][vc_zigzag color=&#8221;white&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;35863&#8243; img_size=&#8221;large&#8221; onclick=&#8221;link_image&#8221; css=&#8221;&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;35864&#8243; img_size=&#8221;large&#8221; onclick=&#8221;link_image&#8221; css=&#8221;&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650255686594{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center p-md-0 pt-5 pb-5&#8243;][vc_column el_class=&#8221;pb-5&#8243;][vc_row_inner el_class=&#8221;pb-5&#8243;][vc_column_inner]<div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0\"><h2 class=\"title title--decorator title--ms d-inline-block\">Te Recomendamos<\/h2><\/div><\/div><div class=\"content-holder\"><div class=\"row  swipper-news-list not--activate-hack \"><div class=\"row -wrapper\"><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/category\/ciencias-sociales\/\">\n                                        Ciencias Sociales<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/wp-content\/uploads\/sites\/18\/2026\/05\/Salario-minimo-2.jpeg\" alt=\"Salario m\u00ednimo v\/s poder adquisitivo: las tensiones econ\u00f3micas entre ingresos reales y el alto costo de vida\" style=\"--smush-placeholder-width: 1600px; --smush-placeholder-aspect-ratio: 1600\/1066;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Lunes 11, Mayo<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/salario-minimo-v-s-poder-adquisitivo-las-tensiones-economicas-entre-ingresos-reales-y-el-alto-costo-de-vida\/\">\n                                    <h3 class=\"small-space\">Salario m\u00ednimo v\/s poder adquisitivo: las tensiones econ\u00f3micas entre ingresos reales y el alto costo de vida<\/h3><\/a>\n\n                                    <p>El economista Pablo Pe\u00f1a aborda el ajuste del gasto p\u00fablico, sus efectos en el mercado interno, el impacto de la guerra en oriente medio y medidas frente a este escenario.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/salario-minimo-v-s-poder-adquisitivo-las-tensiones-economicas-entre-ingresos-reales-y-el-alto-costo-de-vida\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/wp-content\/uploads\/sites\/18\/2026\/04\/Inauguracion-Ano-Academico-2026-6.jpg\" alt=\"Reflexi\u00f3n universitaria: UOH inaugura A\u00f1o Acad\u00e9mico 2026 pensando en los desaf\u00edos de la Educaci\u00f3n Superior\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Mi\u00e9rcoles 29, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/reflexion-universitaria-uoh-inaugura-ano-academico-2026-pensando-en-los-desafios-de-la-educacion-superior\/\">\n                                    <h3 class=\"small-space\">Reflexi\u00f3n universitaria: UOH inaugura A\u00f1o Acad\u00e9mico 2026 pensando en los desaf\u00edos de la Educaci\u00f3n Superior<\/h3><\/a>\n\n                                    <p>La ceremonia promovi\u00f3 el an\u00e1lisis acerca de los cambios educativos que se avecinan dentro de los procesos de formaci\u00f3n universitaria ajustados a contextos digitales.   <\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/reflexion-universitaria-uoh-inaugura-ano-academico-2026-pensando-en-los-desafios-de-la-educacion-superior\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/category\/ciencias-sociales\/\">\n                                        Ciencias Sociales<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/wp-content\/uploads\/sites\/18\/2026\/04\/Estudiantes-de-Derecho-UOH-viven-la-justicia-desde-adentro-en-visita-a-la-Corte-de-Apelaciones.jpeg\" alt=\"Estudiantes de Derecho UOH viven la justicia desde adentro en visita a la Corte de Apelaciones\" style=\"--smush-placeholder-width: 1600px; --smush-placeholder-aspect-ratio: 1600\/1066;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Lunes 27, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/estudiantes-de-derecho-uoh-viven-la-justicia-desde-adentro-en-visita-a-la-corte-de-apelaciones\/\">\n                                    <h3 class=\"small-space\">Estudiantes de Derecho UOH viven la justicia desde adentro en visita a la Corte de Apelaciones<\/h3><\/a>\n\n                                    <p>Las y los estudiantes del Taller de Expresi\u00f3n Oral y Escrita de la secci\u00f3n 1 presenciaron alegatos en vivo y dialogaron con la m\u00e1xima autoridad del tribunal regional.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/estudiantes-de-derecho-uoh-viven-la-justicia-desde-adentro-en-visita-a-la-corte-de-apelaciones\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pagination justify-content-center my-5\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/wp-json\/wp\/v2\/posts\/2470\/\/page\/2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/wp-json\/wp\/v2\/posts\/2470\/\/page\/3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/wp-json\/wp\/v2\/posts\/2470\/\/page\/140\">140<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/wp-json\/wp\/v2\/posts\/2470\/\/page\/2\"><div class=\"icon-pagination-next\"> <?xml version=\"1.0\" ?><svg viewBox=\"0 0 96 96\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><title\/><path d=\"M39.3756,48.0022l30.47-25.39a6.0035,6.0035,0,0,0-7.6878-9.223L26.1563,43.3906a6.0092,6.0092,0,0,0,0,9.2231L62.1578,82.615a6.0035,6.0035,0,0,0,7.6878-9.2231Z\"\/><\/svg> <\/div><\/a><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La regi\u00f3n cuenta con nuevas\/os profesionales en las \u00e1reas de Administraci\u00f3n P\u00fablica, Psicolog\u00eda e Ingenier\u00eda Comercial.<\/p>\n","protected":false},"author":34,"featured_media":2476,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-2470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencias-sociales"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Escuela de Ciencias Sociales titul\u00f3 a 82 egresadas\/os de tres carreras - Escuela de Ciencias de Sociales<\/title>\n<meta name=\"description\" content=\"La regi\u00f3n cuenta con nuevas\/os profesionales en las \u00e1reas de Administraci\u00f3n P\u00fablica, Psicolog\u00eda e Ingenier\u00eda Comercial.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Escuela de Ciencias Sociales titul\u00f3 a 82 egresadas\/os de tres carreras - Escuela de Ciencias de Sociales\" \/>\n<meta property=\"og:description\" content=\"La regi\u00f3n cuenta con nuevas\/os profesionales en las \u00e1reas de Administraci\u00f3n P\u00fablica, Psicolog\u00eda e Ingenier\u00eda Comercial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/escuela-de-ciencias-sociales-titulo-a-82-egresadas-os-de-tres-carreras\/\" \/>\n<meta property=\"og:site_name\" content=\"Escuela de Ciencias de Sociales\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-24T18:12:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-24T20:12:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/wp-content\/uploads\/sites\/18\/2024\/07\/Titulacion-Escuela-de-Ciencias-Sociales-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Universidad de O&#039;Higgins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Universidad de O&#039;Higgins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/escuela-de-ciencias-sociales-titulo-a-82-egresadas-os-de-tres-carreras\/\",\"url\":\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/escuela-de-ciencias-sociales-titulo-a-82-egresadas-os-de-tres-carreras\/\",\"name\":\"Escuela de Ciencias Sociales titul\u00f3 a 82 egresadas\/os de tres carreras - Escuela de Ciencias de Sociales\",\"isPartOf\":{\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/escuela-de-ciencias-sociales-titulo-a-82-egresadas-os-de-tres-carreras\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/escuela-de-ciencias-sociales-titulo-a-82-egresadas-os-de-tres-carreras\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/wp-content\/uploads\/sites\/18\/2024\/07\/Titulacion-Escuela-de-Ciencias-Sociales-1.jpg\",\"datePublished\":\"2024-07-24T18:12:08+00:00\",\"dateModified\":\"2024-07-24T20:12:07+00:00\",\"author\":{\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"description\":\"La regi\u00f3n cuenta con nuevas\/os profesionales en las \u00e1reas de Administraci\u00f3n P\u00fablica, Psicolog\u00eda e Ingenier\u00eda Comercial.\",\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/escuela-de-ciencias-sociales-titulo-a-82-egresadas-os-de-tres-carreras\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/escuela-de-ciencias-sociales-titulo-a-82-egresadas-os-de-tres-carreras\/#primaryimage\",\"url\":\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/wp-content\/uploads\/sites\/18\/2024\/07\/Titulacion-Escuela-de-Ciencias-Sociales-1.jpg\",\"contentUrl\":\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/wp-content\/uploads\/sites\/18\/2024\/07\/Titulacion-Escuela-de-Ciencias-Sociales-1.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/#website\",\"url\":\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/\",\"name\":\"Escuela de Ciencias de Sociales\",\"description\":\"Otro sitio de Sitios de Universidad O'higgins\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\",\"name\":\"Universidad de O'Higgins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"caption\":\"Universidad de O'Higgins\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Escuela de Ciencias Sociales titul\u00f3 a 82 egresadas\/os de tres carreras - Escuela de Ciencias de Sociales","description":"La regi\u00f3n cuenta con nuevas\/os profesionales en las \u00e1reas de Administraci\u00f3n P\u00fablica, Psicolog\u00eda e Ingenier\u00eda Comercial.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Escuela de Ciencias Sociales titul\u00f3 a 82 egresadas\/os de tres carreras - Escuela de Ciencias de Sociales","og_description":"La regi\u00f3n cuenta con nuevas\/os profesionales en las \u00e1reas de Administraci\u00f3n P\u00fablica, Psicolog\u00eda e Ingenier\u00eda Comercial.","og_url":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/escuela-de-ciencias-sociales-titulo-a-82-egresadas-os-de-tres-carreras\/","og_site_name":"Escuela de Ciencias de Sociales","article_published_time":"2024-07-24T18:12:08+00:00","article_modified_time":"2024-07-24T20:12:07+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/wp-content\/uploads\/sites\/18\/2024\/07\/Titulacion-Escuela-de-Ciencias-Sociales-1.jpg","type":"image\/jpeg"}],"author":"Universidad de O'Higgins","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Universidad de O'Higgins","Tiempo estimado de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/escuela-de-ciencias-sociales-titulo-a-82-egresadas-os-de-tres-carreras\/","url":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/escuela-de-ciencias-sociales-titulo-a-82-egresadas-os-de-tres-carreras\/","name":"Escuela de Ciencias Sociales titul\u00f3 a 82 egresadas\/os de tres carreras - Escuela de Ciencias de Sociales","isPartOf":{"@id":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/escuela-de-ciencias-sociales-titulo-a-82-egresadas-os-de-tres-carreras\/#primaryimage"},"image":{"@id":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/escuela-de-ciencias-sociales-titulo-a-82-egresadas-os-de-tres-carreras\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/wp-content\/uploads\/sites\/18\/2024\/07\/Titulacion-Escuela-de-Ciencias-Sociales-1.jpg","datePublished":"2024-07-24T18:12:08+00:00","dateModified":"2024-07-24T20:12:07+00:00","author":{"@id":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"description":"La regi\u00f3n cuenta con nuevas\/os profesionales en las \u00e1reas de Administraci\u00f3n P\u00fablica, Psicolog\u00eda e Ingenier\u00eda Comercial.","inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/escuela-de-ciencias-sociales-titulo-a-82-egresadas-os-de-tres-carreras\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/escuela-de-ciencias-sociales-titulo-a-82-egresadas-os-de-tres-carreras\/#primaryimage","url":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/wp-content\/uploads\/sites\/18\/2024\/07\/Titulacion-Escuela-de-Ciencias-Sociales-1.jpg","contentUrl":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/wp-content\/uploads\/sites\/18\/2024\/07\/Titulacion-Escuela-de-Ciencias-Sociales-1.jpg","width":1000,"height":1000},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/#website","url":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/","name":"Escuela de Ciencias de Sociales","description":"Otro sitio de Sitios de Universidad O'higgins","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f","name":"Universidad de O'Higgins","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","caption":"Universidad de O'Higgins"}}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/wp-json\/wp\/v2\/posts\/2470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/wp-json\/wp\/v2\/comments?post=2470"}],"version-history":[{"count":2,"href":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/wp-json\/wp\/v2\/posts\/2470\/revisions"}],"predecessor-version":[{"id":2475,"href":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/wp-json\/wp\/v2\/posts\/2470\/revisions\/2475"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/wp-json\/wp\/v2\/media\/2476"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/wp-json\/wp\/v2\/media?parent=2470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/wp-json\/wp\/v2\/categories?post=2470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uoh.cl\/escuela-de-ciencias-sociales\/wp-json\/wp\/v2\/tags?post=2470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}