
{"id":858,"date":"2022-10-27T09:58:19","date_gmt":"2022-10-27T12:58:19","guid":{"rendered":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/unidad-de-salud-uoh-realizo-campana-informativa-sobre-prevencion-del-embarazo-no-deseado-y-toma-de-examenes-vih\/"},"modified":"2022-10-27T09:58:19","modified_gmt":"2022-10-27T12:58:19","slug":"unidad-de-salud-uoh-realizo-campana-informativa-sobre-prevencion-del-embarazo-no-deseado-y-toma-de-examenes-vih","status":"publish","type":"post","link":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/unidad-de-salud-uoh-realizo-campana-informativa-sobre-prevencion-del-embarazo-no-deseado-y-toma-de-examenes-vih\/","title":{"rendered":"Unidad de Salud UOH realiz\u00f3 campa\u00f1a informativa sobre prevenci\u00f3n del embarazo no deseado y toma de ex\u00e1menes VIH"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center text-right circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row][vc_column]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\"><span itemprop=\"name\">Equidad de Genero y Diversidades<\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Unidad de Salud UOH realiz\u00f3 campa\u00f1a informativa sobre prevenci\u00f3n del <\/span><meta itemprop=\"position\" content=\"3\" \/><\/ol><\/div><ul class=\"p-0 list-style-none d-inline-block\"><li class=\"p-0\"><a href=https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/category\/comunidad\/ class=\"px-1 py-2\">Comunidad<\/a><\/li><\/ul><div class=\"date_publish_post\"> \u25cf Jue 27 de Octubre 2022<\/div><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block title--decorator  big\">Unidad de Salud UOH realiz\u00f3 campa\u00f1a informativa sobre prevenci\u00f3n del embarazo no deseado y toma de ex\u00e1menes VIH<\/h1><\/div>[vc_row_inner el_class=&#8221;border-separator m-0&#8243;][vc_column_inner width=&#8221;2\/3&#8243;][\/vc_column_inner][vc_column_inner el_class=&#8221;align-items-end-publish&#8221; width=&#8221;1\/3&#8243;]<div class=\"uoh_social_network_component uoh_row col-12 justify-content-end m-0 p-0\"> <div class=\"icon__facebook-share-button\">\n                       <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/unidad-de-salud-uoh-realizo-campana-informativa-sobre-prevencion-del-embarazo-no-deseado-y-toma-de-examenes-vih\/\" target=\"_blank\"> <div class=\"icon__facebook-svg\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22.4px\" height=\"48.3px\" viewBox=\"0 0 22.4 48.3\" style=\"overflow:visible;enable-background:new 0 0 22.4 48.3;\" xml:space=\"preserve\">\n                <defs>\n                <\/defs>\n                <path class=\"st0\" d=\"M22.4,15.6h-7.6v-5c0-1.9,1.2-2.3,2.1-2.3c0.9,0,5.4,0,5.4,0V0l-7.4,0C6.6,0,4.8,6.2,4.8,10.1v5.5H0v8.5h4.8\n                    c0,10.9,0,24.1,0,24.1h10c0,0,0-13.3,0-24.1h6.8L22.4,15.6z\"><\/path>\n                <\/svg><\/a><\/div>\n                    <\/div><div class=\"icon__twitter-share-button\">\n                        <div class=\"icon__twitter-svg\"><a target=\"_blank\" href=\"http:\/\/twitter.com\/share?url=https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/unidad-de-salud-uoh-realizo-campana-informativa-sobre-prevencion-del-embarazo-no-deseado-y-toma-de-examenes-vih\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/a><\/div>\n                        <\/div><div class=\"icon__linkedin-share-button\">\n                        <div class=\"icon__linkedin-svg\">\n                        <a target=\"__blank\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/unidad-de-salud-uoh-realizo-campana-informativa-sobre-prevencion-del-embarazo-no-deseado-y-toma-de-examenes-vih\/\"><svg enable-background=\"new 0 0 100 100\" height=\"100px\" id=\"Layer_1\" version=\"1.1\" viewBox=\"0 0 100 100\" width=\"100px\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><circle cx=\"50\" cy=\"50\" fill=\"#ccc\" r=\"45\"\/><g id=\"LinkedIn_1_\"><rect fill=\"#FFFFFF\" height=\"24.361\" width=\"7.69\" x=\"31.271\" y=\"43.569\"\/><path d=\"M59.968,43.334c-4.406,0-7.165,2.387-7.677,4.058v-3.823h-8.636c0.109,2.03,0,24.361,0,24.361h8.636    V54.748c0-0.733-0.034-1.465,0.19-1.991c0.594-1.464,1.869-2.985,4.162-2.985c2.998,0,4.361,2.253,4.361,5.552V67.93h8.721V54.384    C69.726,46.839,65.432,43.334,59.968,43.334z\" fill=\"#FFFFFF\"\/><path d=\"M34.973,32.069c-2.839,0-4.696,1.823-4.696,4.229c0,2.361,1.804,4.224,4.589,4.224h0.054    c2.891,0,4.69-1.869,4.69-4.229C39.555,33.888,37.81,32.069,34.973,32.069z\" fill=\"#FFFFFF\"\/><\/g><\/g><\/svg><\/a><\/div>\n\n            <\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_single_image image=&#8221;12039&#8243; img_size=&#8221;large&#8221;][vc_column_text]\u00a0[\/vc_column_text][vc_column_text]<em>Las actividades se enmarcaron en la celebraci\u00f3n del Mes de la Salud Integral en la Universidad de O\u2019Higgins. <\/em>[\/vc_column_text]<div class=\"author_wp_class\"> Escrito por <span>Universidad de O'Higgins<\/span><\/div>[vc_column_text]\u00a0[\/vc_column_text][vc_column_text]En el marco de la celebraci\u00f3n del Mes de la Salud Integral, que se desarrolla en diversas universidades del pa\u00eds, la Unidad de Salud de la Direcci\u00f3n de Asuntos Estudiantiles de la Universidad de O\u2019Higgins (UOH), llev\u00f3 a cabo la Semana de la Salud Integral y Sexual con variadas actividades en ambos campus.<\/p>\n<p>El objetivo de las actividades fue orientar a los\/as estudiantes y funcionarios\/as respecto al autocuidado e importancia que tiene la prevenci\u00f3n de enfermedades de transmisi\u00f3n sexual y el c\u00e1ncer de mama.<\/p>\n<p>Stands de la Unidad de Salud entregaron preservativos e informaci\u00f3n para la prevenci\u00f3n del embarazo con diversos m\u00e9todos anticonceptivos, como preservativos femeninos y masculinos. Adem\u00e1s, se cont\u00f3 con la realizaci\u00f3n de tomas r\u00e1pidas de VIH para estudiantes y funcionarios, en los campus Colchagua y Rancagua.<\/p>\n<p>Para la matrona de la Unidad de Salud de la Direcci\u00f3n de Asuntos Estudiantiles, Francisca Rojas, estas instancias \u201cayudan a que los y las estudiantes obtengan informaci\u00f3n y orientaci\u00f3n sobre la salud sexual de forma f\u00e1cil, directa y cercana, sobre todo en tem\u00e1ticas como la prevenci\u00f3n de embarazo y prevenci\u00f3n de enfermedades de trasmisi\u00f3n sexual, temas de alto inter\u00e9s por parte del estudiantado\u201d.<\/p>\n<p>Para finalizar, la funcionaria UOH adelant\u00f3 que \u201cdentro de las pr\u00f3ximas actividades que tendremos, como parte del D\u00eda de la Prevenci\u00f3n, est\u00e1 una toma de test r\u00e1pido de VIH para estudiantes y funcionarios\/as en el campus Rancagua y Colchagua, con el fin de concientizar sobre la enfermedad. As\u00ed que quienes no pudieron participar esta vez, puede planificarse para hacerlo pr\u00f3ximamente\u201d.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650255686594{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center text-right p-md-0 pt-5 pb-5&#8243;][vc_column el_class=&#8221;pb-5&#8243;][vc_row_inner el_class=&#8221;pb-5&#8243;][vc_column_inner]<div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0\"><h2 class=\"title title--decorator title--ms d-inline-block\">Te Recomendamos<\/h2><\/div><\/div><div class=\"content-holder\"><div class=\"row  swipper-news-list not--activate-hack \"><div class=\"row -wrapper\"><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/wp-content\/uploads\/sites\/20\/2026\/04\/Inauguracion-Ano-Academico-2026-6.jpg\" alt=\"Reflexi\u00f3n universitaria: UOH inaugura A\u00f1o Acad\u00e9mico 2026 pensando en los desaf\u00edos de la Educaci\u00f3n Superior\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Mi\u00e9rcoles 29, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/reflexion-universitaria-uoh-inaugura-ano-academico-2026-pensando-en-los-desafios-de-la-educacion-superior\/\">\n                                    <h3 class=\"small-space\">Reflexi\u00f3n universitaria: UOH inaugura A\u00f1o Acad\u00e9mico 2026 pensando en los desaf\u00edos de la Educaci\u00f3n Superior<\/h3><\/a>\n\n                                    <p>La ceremonia promovi\u00f3 el an\u00e1lisis acerca de los cambios educativos que se avecinan dentro de los procesos de formaci\u00f3n universitaria ajustados a contextos digitales.   <\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/reflexion-universitaria-uoh-inaugura-ano-academico-2026-pensando-en-los-desafios-de-la-educacion-superior\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/category\/cuech\/\">\n                                        CUECH<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/wp-content\/uploads\/sites\/20\/2026\/04\/DSC_2431-scaled.jpg\" alt=\"Universidades estatales sellan hoja de ruta 2030: Red Desarrollo Sustentable entra en fase de consolidaci\u00f3n\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/1707;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Mi\u00e9rcoles 15, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/universidades-estatales-sellan-hoja-de-ruta-2030-red-desarrollo-sustentable-entra-en-fase-de-consolidacion\/\">\n                                    <h3 class=\"small-space\">Universidades estatales sellan hoja de ruta 2030: Red Desarrollo Sustentable entra en fase de consolidaci\u00f3n<\/h3><\/a>\n\n                                    <p>En el Plenario realizado en la Universidad de O'Higgins, los 18 planteles p\u00fablicos definieron sus metas estrat\u00e9gicas para el periodo 2026-2030. El plan priorizar\u00e1 la institucionalizaci\u00f3n de capacidades, un diplomado para organismos p\u00fablicos y la medici\u00f3n de la huella h\u00eddrica en los campus.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/universidades-estatales-sellan-hoja-de-ruta-2030-red-desarrollo-sustentable-entra-en-fase-de-consolidacion\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/category\/genero\/\">\n                                        G\u00e9nero<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/wp-content\/uploads\/sites\/20\/2026\/04\/IMG_0028-scaled.jpg\" alt=\"Charlas, cultura y encuentros marcaron la conmemoraci\u00f3n del Mes de las Mujeres en la UOH\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/1707;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Lunes 6, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/charlas-cultura-y-encuentros-marcaron-la-conmemoracion-del-mes-de-las-mujeres-en-la-uoh\/\">\n                                    <h3 class=\"small-space\">Charlas, cultura y encuentros marcaron la conmemoraci\u00f3n del Mes de las Mujeres en la UOH<\/h3><\/a>\n\n                                    <p>Durante marzo, nuestra Casa de Estudios promovi\u00f3 el di\u00e1logo y la reflexi\u00f3n en torno a los derechos de las mujeres. Las iniciativas reunieron a estudiantes, acad\u00e9micas\/os y funcionarias\/os en espacios de reflexi\u00f3n y participaci\u00f3n. <\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/charlas-cultura-y-encuentros-marcaron-la-conmemoracion-del-mes-de-las-mujeres-en-la-uoh\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pagination justify-content-center my-5\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/wp-json\/wp\/v2\/posts\/858\/\/page\/2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/wp-json\/wp\/v2\/posts\/858\/\/page\/3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/wp-json\/wp\/v2\/posts\/858\/\/page\/66\">66<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/wp-json\/wp\/v2\/posts\/858\/\/page\/2\"><div class=\"icon-pagination-next\"> <?xml version=\"1.0\" ?><svg viewBox=\"0 0 96 96\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><title\/><path d=\"M39.3756,48.0022l30.47-25.39a6.0035,6.0035,0,0,0-7.6878-9.223L26.1563,43.3906a6.0092,6.0092,0,0,0,0,9.2231L62.1578,82.615a6.0035,6.0035,0,0,0,7.6878-9.2231Z\"\/><\/svg> <\/div><\/a><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Las actividades se enmarcaron en la celebraci\u00f3n del Mes de la Salud Integral en la Universidad de O\u2019Higgins. <\/p>\n","protected":false},"author":34,"featured_media":859,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Unidad de Salud UOH realiz\u00f3 campa\u00f1a informativa sobre prevenci\u00f3n del embarazo no deseado y toma de ex\u00e1menes VIH - Equidad de Genero y Diversidades<\/title>\n<meta name=\"description\" content=\"Las actividades se enmarcaron en la celebraci\u00f3n del Mes de la Salud Integral en la Universidad de O\u2019Higgins.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unidad de Salud UOH realiz\u00f3 campa\u00f1a informativa sobre prevenci\u00f3n del embarazo no deseado y toma de ex\u00e1menes VIH - Equidad de Genero y Diversidades\" \/>\n<meta property=\"og:description\" content=\"Las actividades se enmarcaron en la celebraci\u00f3n del Mes de la Salud Integral en la Universidad de O\u2019Higgins.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/unidad-de-salud-uoh-realizo-campana-informativa-sobre-prevencion-del-embarazo-no-deseado-y-toma-de-examenes-vih\/\" \/>\n<meta property=\"og:site_name\" content=\"Equidad de Genero y Diversidades\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-27T12:58:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/wp-content\/uploads\/sites\/20\/2022\/10\/Mes-Salud-Integral.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Universidad de O&#039;Higgins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Universidad de O&#039;Higgins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/unidad-de-salud-uoh-realizo-campana-informativa-sobre-prevencion-del-embarazo-no-deseado-y-toma-de-examenes-vih\/\",\"url\":\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/unidad-de-salud-uoh-realizo-campana-informativa-sobre-prevencion-del-embarazo-no-deseado-y-toma-de-examenes-vih\/\",\"name\":\"Unidad de Salud UOH realiz\u00f3 campa\u00f1a informativa sobre prevenci\u00f3n del embarazo no deseado y toma de ex\u00e1menes VIH - Equidad de Genero y Diversidades\",\"isPartOf\":{\"@id\":\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/unidad-de-salud-uoh-realizo-campana-informativa-sobre-prevencion-del-embarazo-no-deseado-y-toma-de-examenes-vih\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/unidad-de-salud-uoh-realizo-campana-informativa-sobre-prevencion-del-embarazo-no-deseado-y-toma-de-examenes-vih\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/wp-content\/uploads\/sites\/20\/2022\/10\/Mes-Salud-Integral.jpg\",\"datePublished\":\"2022-10-27T12:58:19+00:00\",\"author\":{\"@id\":\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"description\":\"Las actividades se enmarcaron en la celebraci\u00f3n del Mes de la Salud Integral en la Universidad de O\u2019Higgins.\",\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/unidad-de-salud-uoh-realizo-campana-informativa-sobre-prevencion-del-embarazo-no-deseado-y-toma-de-examenes-vih\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/unidad-de-salud-uoh-realizo-campana-informativa-sobre-prevencion-del-embarazo-no-deseado-y-toma-de-examenes-vih\/#primaryimage\",\"url\":\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/wp-content\/uploads\/sites\/20\/2022\/10\/Mes-Salud-Integral.jpg\",\"contentUrl\":\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/wp-content\/uploads\/sites\/20\/2022\/10\/Mes-Salud-Integral.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/#website\",\"url\":\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/\",\"name\":\"Equidad de Genero y Diversidades\",\"description\":\"Otro sitio de Sitios de Universidad O'higgins\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\",\"name\":\"Universidad de O'Higgins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"caption\":\"Universidad de O'Higgins\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unidad de Salud UOH realiz\u00f3 campa\u00f1a informativa sobre prevenci\u00f3n del embarazo no deseado y toma de ex\u00e1menes VIH - Equidad de Genero y Diversidades","description":"Las actividades se enmarcaron en la celebraci\u00f3n del Mes de la Salud Integral en la Universidad de O\u2019Higgins.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Unidad de Salud UOH realiz\u00f3 campa\u00f1a informativa sobre prevenci\u00f3n del embarazo no deseado y toma de ex\u00e1menes VIH - Equidad de Genero y Diversidades","og_description":"Las actividades se enmarcaron en la celebraci\u00f3n del Mes de la Salud Integral en la Universidad de O\u2019Higgins.","og_url":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/unidad-de-salud-uoh-realizo-campana-informativa-sobre-prevencion-del-embarazo-no-deseado-y-toma-de-examenes-vih\/","og_site_name":"Equidad de Genero y Diversidades","article_published_time":"2022-10-27T12:58:19+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/wp-content\/uploads\/sites\/20\/2022\/10\/Mes-Salud-Integral.jpg","type":"image\/jpeg"}],"author":"Universidad de O'Higgins","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Universidad de O'Higgins","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/unidad-de-salud-uoh-realizo-campana-informativa-sobre-prevencion-del-embarazo-no-deseado-y-toma-de-examenes-vih\/","url":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/unidad-de-salud-uoh-realizo-campana-informativa-sobre-prevencion-del-embarazo-no-deseado-y-toma-de-examenes-vih\/","name":"Unidad de Salud UOH realiz\u00f3 campa\u00f1a informativa sobre prevenci\u00f3n del embarazo no deseado y toma de ex\u00e1menes VIH - Equidad de Genero y Diversidades","isPartOf":{"@id":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/unidad-de-salud-uoh-realizo-campana-informativa-sobre-prevencion-del-embarazo-no-deseado-y-toma-de-examenes-vih\/#primaryimage"},"image":{"@id":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/unidad-de-salud-uoh-realizo-campana-informativa-sobre-prevencion-del-embarazo-no-deseado-y-toma-de-examenes-vih\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/wp-content\/uploads\/sites\/20\/2022\/10\/Mes-Salud-Integral.jpg","datePublished":"2022-10-27T12:58:19+00:00","author":{"@id":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"description":"Las actividades se enmarcaron en la celebraci\u00f3n del Mes de la Salud Integral en la Universidad de O\u2019Higgins.","inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/unidad-de-salud-uoh-realizo-campana-informativa-sobre-prevencion-del-embarazo-no-deseado-y-toma-de-examenes-vih\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/unidad-de-salud-uoh-realizo-campana-informativa-sobre-prevencion-del-embarazo-no-deseado-y-toma-de-examenes-vih\/#primaryimage","url":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/wp-content\/uploads\/sites\/20\/2022\/10\/Mes-Salud-Integral.jpg","contentUrl":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/wp-content\/uploads\/sites\/20\/2022\/10\/Mes-Salud-Integral.jpg","width":1000,"height":1000},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/#website","url":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/","name":"Equidad de Genero y Diversidades","description":"Otro sitio de Sitios de Universidad O'higgins","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f","name":"Universidad de O'Higgins","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","caption":"Universidad de O'Higgins"}}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/wp-json\/wp\/v2\/posts\/858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/wp-json\/wp\/v2\/comments?post=858"}],"version-history":[{"count":0,"href":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/wp-json\/wp\/v2\/posts\/858\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/wp-json\/wp\/v2\/media\/859"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/wp-json\/wp\/v2\/media?parent=858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/wp-json\/wp\/v2\/categories?post=858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uoh.cl\/equidad-de-genero-y-diversidades\/wp-json\/wp\/v2\/tags?post=858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}