
{"id":111,"date":"2025-06-06T16:47:33","date_gmt":"2025-06-06T19:47:33","guid":{"rendered":"https:\/\/www.uoh.cl\/dgp\/vicerrectoria-de-administracion-y-finanzas-tiene-un-nuevo-espacio-para-desarrollar-sus-funciones\/"},"modified":"2025-06-06T16:47:33","modified_gmt":"2025-06-06T19:47:33","slug":"vicerrectoria-de-administracion-y-finanzas-tiene-un-nuevo-espacio-para-desarrollar-sus-funciones","status":"publish","type":"post","link":"https:\/\/www.uoh.cl\/dgp\/vicerrectoria-de-administracion-y-finanzas-tiene-un-nuevo-espacio-para-desarrollar-sus-funciones\/","title":{"rendered":"Vicerrector\u00eda de Administraci\u00f3n y Finanzas tiene un nuevo espacio para desarrollar sus funciones"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row][vc_column]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/dgp\"><span itemprop=\"name\">Direcci\u00f3n de Gesti\u00f3n de Personas<\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/dgp\/noticias\/\"><span itemprop=\"name\">Noticias<\/span><\/a><meta itemprop=\"position\" content=\"3\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Vicerrector\u00eda de Administraci\u00f3n y Finanzas tiene un nuevo espacio para <\/span><meta itemprop=\"position\" content=\"4\" \/><\/ol><\/div><ul class=\"p-0 list-style-none d-inline-block\"><li class=\"p-0\"><a href=https:\/\/www.uoh.cl\/dgp\/category\/institucional\/ class=\"px-1 py-2\">Institucional<\/a><\/li><\/ul><div class=\"date_publish_post\"> \u25cf Vie 06 de Junio 2025<\/div><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block title--decorator  big\">Vicerrector\u00eda de Administraci\u00f3n y Finanzas tiene un nuevo espacio para desarrollar sus funciones<\/h1><\/div>[vc_row_inner el_class=&#8221;border-separator m-0&#8243;][vc_column_inner width=&#8221;2\/3&#8243;]<div class=\"author_wp_class\"> Escrito por <span>Universidad de O'Higgins<\/span><\/div>[\/vc_column_inner][vc_column_inner el_class=&#8221;align-items-end-publish&#8221; width=&#8221;1\/3&#8243;]<div class=\"uoh_social_network_component uoh_row col-12 justify-content-end m-0 p-0\"> <div class=\"icon__facebook-share-button\">\n                       <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.uoh.cl\/dgp\/vicerrectoria-de-administracion-y-finanzas-tiene-un-nuevo-espacio-para-desarrollar-sus-funciones\/\" target=\"_blank\"> <div class=\"icon__facebook-svg\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22.4px\" height=\"48.3px\" viewBox=\"0 0 22.4 48.3\" style=\"overflow:visible;enable-background:new 0 0 22.4 48.3;\" xml:space=\"preserve\">\n                <defs>\n                <\/defs>\n                <path class=\"st0\" d=\"M22.4,15.6h-7.6v-5c0-1.9,1.2-2.3,2.1-2.3c0.9,0,5.4,0,5.4,0V0l-7.4,0C6.6,0,4.8,6.2,4.8,10.1v5.5H0v8.5h4.8\n                    c0,10.9,0,24.1,0,24.1h10c0,0,0-13.3,0-24.1h6.8L22.4,15.6z\"><\/path>\n                <\/svg><\/a><\/div>\n                    <\/div><div class=\"icon__twitter-share-button\">\n                        <div class=\"icon__twitter-svg\"><a target=\"_blank\" href=\"http:\/\/twitter.com\/share?url=https:\/\/www.uoh.cl\/dgp\/vicerrectoria-de-administracion-y-finanzas-tiene-un-nuevo-espacio-para-desarrollar-sus-funciones\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/a><\/div>\n                        <\/div><div class=\"icon__linkedin-share-button\">\n                        <div class=\"icon__linkedin-svg\">\n                        <a target=\"__blank\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.uoh.cl\/dgp\/vicerrectoria-de-administracion-y-finanzas-tiene-un-nuevo-espacio-para-desarrollar-sus-funciones\/\"><svg enable-background=\"new 0 0 100 100\" height=\"100px\" id=\"Layer_1\" version=\"1.1\" viewBox=\"0 0 100 100\" width=\"100px\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><circle cx=\"50\" cy=\"50\" fill=\"#ccc\" r=\"45\"\/><g id=\"LinkedIn_1_\"><rect fill=\"#FFFFFF\" height=\"24.361\" width=\"7.69\" x=\"31.271\" y=\"43.569\"\/><path d=\"M59.968,43.334c-4.406,0-7.165,2.387-7.677,4.058v-3.823h-8.636c0.109,2.03,0,24.361,0,24.361h8.636    V54.748c0-0.733-0.034-1.465,0.19-1.991c0.594-1.464,1.869-2.985,4.162-2.985c2.998,0,4.361,2.253,4.361,5.552V67.93h8.721V54.384    C69.726,46.839,65.432,43.334,59.968,43.334z\" fill=\"#FFFFFF\"\/><path d=\"M34.973,32.069c-2.839,0-4.696,1.823-4.696,4.229c0,2.361,1.804,4.224,4.589,4.224h0.054    c2.891,0,4.69-1.869,4.69-4.229C39.555,33.888,37.81,32.069,34.973,32.069z\" fill=\"#FFFFFF\"\/><\/g><\/g><\/svg><\/a><\/div>\n\n            <\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_single_image image=&#8221;47645&#8243; img_size=&#8221;1500&#215;1000&#8243; add_caption=&#8221;yes&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; css=&#8221;&#8221;][vc_column_text]\u00a0[\/vc_column_text][vc_column_text css=&#8221;&#8221;]<\/p>\n<ul>\n<li><em>La inauguraci\u00f3n de las nuevas dependencias representa un paso importante en la consolidaci\u00f3n de los equipos administrativos en espacios m\u00e1s integrados, acogedores y funcionales. <\/em><\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_column_text]\u00a0[\/vc_column_text][vc_column_text css=&#8221;&#8221;]Con sentido de pertenencia y comunidad se inaugur\u00f3 el nuevo edificio que alberga a los equipos de la Direcci\u00f3n de Gesti\u00f3n de Personas, Gesti\u00f3n de Operaciones y Gesti\u00f3n Financiera e Infraestructura, todos pertenecientes a la <a href=\"https:\/\/www.uoh.cl\/universidad\/vicerrectoria-de-administracion-y-finanzas\/\">Vicerrector\u00eda de Administraci\u00f3n y Finanzas<\/a> de la <a href=\"http:\/\/www.uoh.cl\/\">Universidad de O\u2019Higgins<\/a>.<\/p>\n<p>El nuevo edificio, ubicado en la calle Jos\u00e9 Domingo Mujica 343 de Rancagua, fue adquirido en febrero de 2025 con una inversi\u00f3n de 20.000 UF. Se trata de 450 metros cuadrados y 60 puestos de trabajo, espacio que busca mejorar las condiciones laborales, fomentar la colaboraci\u00f3n y reforzar el compromiso institucional.<\/p>\n<p>Durante la ceremonia, la Rectora Fernanda Kri Amar valor\u00f3 el esfuerzo detr\u00e1s del traslado y destac\u00f3 la importancia de contar con espacios dignos, integrados y dise\u00f1ados para el bienestar de las\/os funcionarias\/os.<\/p>\n<p>En ese sentido, la Vicerrectora de Administraci\u00f3n y Finanzas, Ang\u00e9lica Pe\u00f1a, destac\u00f3 que este edificio marca un hito en los 10 a\u00f1os de la Universidad, reafirmando la eficiencia, la transparencia y la vocaci\u00f3n p\u00fablica. \u201cQueremos que este sea un espacio de acogida, encuentro y servicio para toda la UOH\u201d, enfatiz\u00f3.<\/p>\n<p>Este nuevo paso busca optimizar el funcionamiento interno y seguir fortaleciendo los lazos entre equipos en conjunto con toda la comunidad universitaria.[\/vc_column_text][vc_zigzag color=&#8221;white&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;47646&#8243; img_size=&#8221;700&#215;450&#8243; onclick=&#8221;link_image&#8221; css=&#8221;&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;47651&#8243; img_size=&#8221;700&#215;450&#8243; onclick=&#8221;link_image&#8221; css=&#8221;&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;47648&#8243; img_size=&#8221;700&#215;450&#8243; onclick=&#8221;link_image&#8221; css=&#8221;&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650255686594{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center p-md-0 pt-5 pb-5&#8243;][vc_column el_class=&#8221;pb-5&#8243;][vc_row_inner el_class=&#8221;pb-5&#8243;][vc_column_inner]<div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0\"><h2 class=\"title title--decorator title--ms d-inline-block\">Te Recomendamos<\/h2><\/div><\/div><div class=\"content-holder\"><div class=\"row  swipper-news-list not--activate-hack \"><div class=\"row -wrapper\"><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/dgp\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/dgp\/wp-content\/uploads\/sites\/46\/2026\/04\/Inauguracion-Ano-Academico-2026-6.jpg\" alt=\"Reflexi\u00f3n universitaria: UOH inaugura A\u00f1o Acad\u00e9mico 2026 pensando en los desaf\u00edos de la Educaci\u00f3n Superior\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Mi\u00e9rcoles 29, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/dgp\/reflexion-universitaria-uoh-inaugura-ano-academico-2026-pensando-en-los-desafios-de-la-educacion-superior\/\">\n                                    <h3 class=\"small-space\">Reflexi\u00f3n universitaria: UOH inaugura A\u00f1o Acad\u00e9mico 2026 pensando en los desaf\u00edos de la Educaci\u00f3n Superior<\/h3><\/a>\n\n                                    <p>La ceremonia promovi\u00f3 el an\u00e1lisis acerca de los cambios educativos que se avecinan dentro de los procesos de formaci\u00f3n universitaria ajustados a contextos digitales.   <\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/dgp\/reflexion-universitaria-uoh-inaugura-ano-academico-2026-pensando-en-los-desafios-de-la-educacion-superior\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/dgp\/category\/cuech\/\">\n                                        CUECH<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/dgp\/wp-content\/uploads\/sites\/46\/2026\/04\/DSC_2431-scaled.jpg\" alt=\"Universidades estatales sellan hoja de ruta 2030: Red Desarrollo Sustentable entra en fase de consolidaci\u00f3n\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/1707;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Mi\u00e9rcoles 15, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/dgp\/universidades-estatales-sellan-hoja-de-ruta-2030-red-desarrollo-sustentable-entra-en-fase-de-consolidacion\/\">\n                                    <h3 class=\"small-space\">Universidades estatales sellan hoja de ruta 2030: Red Desarrollo Sustentable entra en fase de consolidaci\u00f3n<\/h3><\/a>\n\n                                    <p>En el Plenario realizado en la Universidad de O'Higgins, los 18 planteles p\u00fablicos definieron sus metas estrat\u00e9gicas para el periodo 2026-2030. El plan priorizar\u00e1 la institucionalizaci\u00f3n de capacidades, un diplomado para organismos p\u00fablicos y la medici\u00f3n de la huella h\u00eddrica en los campus.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/dgp\/universidades-estatales-sellan-hoja-de-ruta-2030-red-desarrollo-sustentable-entra-en-fase-de-consolidacion\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/dgp\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/dgp\/wp-content\/uploads\/sites\/46\/2026\/01\/36_Frontis.jpg\" alt=\"UOH cuenta con nuevo Plan de Desarrollo Estrat\u00e9gico\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Jueves 8, Enero<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/dgp\/uoh-cuenta-con-nuevo-plan-de-desarrollo-estrategico\/\">\n                                    <h3 class=\"small-space\">UOH cuenta con nuevo Plan de Desarrollo Estrat\u00e9gico<\/h3><\/a>\n\n                                    <p>Su proceso de construcci\u00f3n se realiz\u00f3 entre agosto de 2024 y noviembre de 2025.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/dgp\/uoh-cuenta-con-nuevo-plan-de-desarrollo-estrategico\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pagination justify-content-center my-5\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/dgp\/wp-json\/wp\/v2\/posts\/111\/\/page\/2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/dgp\/wp-json\/wp\/v2\/posts\/111\/\/page\/3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/dgp\/wp-json\/wp\/v2\/posts\/111\/\/page\/10\">10<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/www.uoh.cl\/dgp\/wp-json\/wp\/v2\/posts\/111\/\/page\/2\"><div class=\"icon-pagination-next\"> <?xml version=\"1.0\" ?><svg viewBox=\"0 0 96 96\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><title\/><path d=\"M39.3756,48.0022l30.47-25.39a6.0035,6.0035,0,0,0-7.6878-9.223L26.1563,43.3906a6.0092,6.0092,0,0,0,0,9.2231L62.1578,82.615a6.0035,6.0035,0,0,0,7.6878-9.2231Z\"\/><\/svg> <\/div><\/a><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La inauguraci\u00f3n de las nuevas dependencias representa un paso importante en la consolidaci\u00f3n de los equipos administrativos en espacios m\u00e1s integrados, acogedores y funcionales. <\/p>\n","protected":false},"author":34,"featured_media":112,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-111","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucional"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vicerrector\u00eda de Administraci\u00f3n y Finanzas tiene un nuevo espacio para desarrollar sus funciones - Direcci\u00f3n de Gesti\u00f3n de Personas<\/title>\n<meta name=\"description\" content=\"La inauguraci\u00f3n de las nuevas dependencias representa un paso importante en la consolidaci\u00f3n de los equipos administrativos en espacios m\u00e1s integrados, acogedores y funcionales.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vicerrector\u00eda de Administraci\u00f3n y Finanzas tiene un nuevo espacio para desarrollar sus funciones - Direcci\u00f3n de Gesti\u00f3n de Personas\" \/>\n<meta property=\"og:description\" content=\"La inauguraci\u00f3n de las nuevas dependencias representa un paso importante en la consolidaci\u00f3n de los equipos administrativos en espacios m\u00e1s integrados, acogedores y funcionales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/dgp\/vicerrectoria-de-administracion-y-finanzas-tiene-un-nuevo-espacio-para-desarrollar-sus-funciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Direcci\u00f3n de Gesti\u00f3n de Personas\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-06T19:47:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uoh.cl\/dgp\/wp-content\/uploads\/sites\/46\/2025\/06\/Vicerrectoria-de-Administracion-y-Finanzas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Universidad de O&#039;Higgins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Universidad de O&#039;Higgins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uoh.cl\/dgp\/vicerrectoria-de-administracion-y-finanzas-tiene-un-nuevo-espacio-para-desarrollar-sus-funciones\/\",\"url\":\"https:\/\/www.uoh.cl\/dgp\/vicerrectoria-de-administracion-y-finanzas-tiene-un-nuevo-espacio-para-desarrollar-sus-funciones\/\",\"name\":\"Vicerrector\u00eda de Administraci\u00f3n y Finanzas tiene un nuevo espacio para desarrollar sus funciones - Direcci\u00f3n de Gesti\u00f3n de Personas\",\"isPartOf\":{\"@id\":\"https:\/\/www.uoh.cl\/dgp\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uoh.cl\/dgp\/vicerrectoria-de-administracion-y-finanzas-tiene-un-nuevo-espacio-para-desarrollar-sus-funciones\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uoh.cl\/dgp\/vicerrectoria-de-administracion-y-finanzas-tiene-un-nuevo-espacio-para-desarrollar-sus-funciones\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uoh.cl\/dgp\/wp-content\/uploads\/sites\/46\/2025\/06\/Vicerrectoria-de-Administracion-y-Finanzas.jpg\",\"datePublished\":\"2025-06-06T19:47:33+00:00\",\"author\":{\"@id\":\"https:\/\/www.uoh.cl\/dgp\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"description\":\"La inauguraci\u00f3n de las nuevas dependencias representa un paso importante en la consolidaci\u00f3n de los equipos administrativos en espacios m\u00e1s integrados, acogedores y funcionales.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.uoh.cl\/dgp\/vicerrectoria-de-administracion-y-finanzas-tiene-un-nuevo-espacio-para-desarrollar-sus-funciones\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uoh.cl\/dgp\/vicerrectoria-de-administracion-y-finanzas-tiene-un-nuevo-espacio-para-desarrollar-sus-funciones\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/dgp\/vicerrectoria-de-administracion-y-finanzas-tiene-un-nuevo-espacio-para-desarrollar-sus-funciones\/#primaryimage\",\"url\":\"https:\/\/www.uoh.cl\/dgp\/wp-content\/uploads\/sites\/46\/2025\/06\/Vicerrectoria-de-Administracion-y-Finanzas.jpg\",\"contentUrl\":\"https:\/\/www.uoh.cl\/dgp\/wp-content\/uploads\/sites\/46\/2025\/06\/Vicerrectoria-de-Administracion-y-Finanzas.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.uoh.cl\/dgp\/vicerrectoria-de-administracion-y-finanzas-tiene-un-nuevo-espacio-para-desarrollar-sus-funciones\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.uoh.cl\/dgp\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vicerrector\u00eda de Administraci\u00f3n y Finanzas tiene un nuevo espacio para desarrollar sus funciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uoh.cl\/dgp\/#website\",\"url\":\"https:\/\/www.uoh.cl\/dgp\/\",\"name\":\"Direcci\u00f3n de Gesti\u00f3n de Personas\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uoh.cl\/dgp\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uoh.cl\/dgp\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\",\"name\":\"Universidad de O'Higgins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/dgp\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"caption\":\"Universidad de O'Higgins\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vicerrector\u00eda de Administraci\u00f3n y Finanzas tiene un nuevo espacio para desarrollar sus funciones - Direcci\u00f3n de Gesti\u00f3n de Personas","description":"La inauguraci\u00f3n de las nuevas dependencias representa un paso importante en la consolidaci\u00f3n de los equipos administrativos en espacios m\u00e1s integrados, acogedores y funcionales.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Vicerrector\u00eda de Administraci\u00f3n y Finanzas tiene un nuevo espacio para desarrollar sus funciones - Direcci\u00f3n de Gesti\u00f3n de Personas","og_description":"La inauguraci\u00f3n de las nuevas dependencias representa un paso importante en la consolidaci\u00f3n de los equipos administrativos en espacios m\u00e1s integrados, acogedores y funcionales.","og_url":"https:\/\/www.uoh.cl\/dgp\/vicerrectoria-de-administracion-y-finanzas-tiene-un-nuevo-espacio-para-desarrollar-sus-funciones\/","og_site_name":"Direcci\u00f3n de Gesti\u00f3n de Personas","article_published_time":"2025-06-06T19:47:33+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.uoh.cl\/dgp\/wp-content\/uploads\/sites\/46\/2025\/06\/Vicerrectoria-de-Administracion-y-Finanzas.jpg","type":"image\/jpeg"}],"author":"Universidad de O'Higgins","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Universidad de O'Higgins","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/dgp\/vicerrectoria-de-administracion-y-finanzas-tiene-un-nuevo-espacio-para-desarrollar-sus-funciones\/","url":"https:\/\/www.uoh.cl\/dgp\/vicerrectoria-de-administracion-y-finanzas-tiene-un-nuevo-espacio-para-desarrollar-sus-funciones\/","name":"Vicerrector\u00eda de Administraci\u00f3n y Finanzas tiene un nuevo espacio para desarrollar sus funciones - Direcci\u00f3n de Gesti\u00f3n de Personas","isPartOf":{"@id":"https:\/\/www.uoh.cl\/dgp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uoh.cl\/dgp\/vicerrectoria-de-administracion-y-finanzas-tiene-un-nuevo-espacio-para-desarrollar-sus-funciones\/#primaryimage"},"image":{"@id":"https:\/\/www.uoh.cl\/dgp\/vicerrectoria-de-administracion-y-finanzas-tiene-un-nuevo-espacio-para-desarrollar-sus-funciones\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/dgp\/wp-content\/uploads\/sites\/46\/2025\/06\/Vicerrectoria-de-Administracion-y-Finanzas.jpg","datePublished":"2025-06-06T19:47:33+00:00","author":{"@id":"https:\/\/www.uoh.cl\/dgp\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"description":"La inauguraci\u00f3n de las nuevas dependencias representa un paso importante en la consolidaci\u00f3n de los equipos administrativos en espacios m\u00e1s integrados, acogedores y funcionales.","breadcrumb":{"@id":"https:\/\/www.uoh.cl\/dgp\/vicerrectoria-de-administracion-y-finanzas-tiene-un-nuevo-espacio-para-desarrollar-sus-funciones\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/dgp\/vicerrectoria-de-administracion-y-finanzas-tiene-un-nuevo-espacio-para-desarrollar-sus-funciones\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/dgp\/vicerrectoria-de-administracion-y-finanzas-tiene-un-nuevo-espacio-para-desarrollar-sus-funciones\/#primaryimage","url":"https:\/\/www.uoh.cl\/dgp\/wp-content\/uploads\/sites\/46\/2025\/06\/Vicerrectoria-de-Administracion-y-Finanzas.jpg","contentUrl":"https:\/\/www.uoh.cl\/dgp\/wp-content\/uploads\/sites\/46\/2025\/06\/Vicerrectoria-de-Administracion-y-Finanzas.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.uoh.cl\/dgp\/vicerrectoria-de-administracion-y-finanzas-tiene-un-nuevo-espacio-para-desarrollar-sus-funciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.uoh.cl\/dgp\/"},{"@type":"ListItem","position":2,"name":"Vicerrector\u00eda de Administraci\u00f3n y Finanzas tiene un nuevo espacio para desarrollar sus funciones"}]},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/dgp\/#website","url":"https:\/\/www.uoh.cl\/dgp\/","name":"Direcci\u00f3n de Gesti\u00f3n de Personas","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/dgp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/www.uoh.cl\/dgp\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f","name":"Universidad de O'Higgins","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/dgp\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","caption":"Universidad de O'Higgins"}}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/dgp\/wp-json\/wp\/v2\/posts\/111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/dgp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uoh.cl\/dgp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/dgp\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/dgp\/wp-json\/wp\/v2\/comments?post=111"}],"version-history":[{"count":0,"href":"https:\/\/www.uoh.cl\/dgp\/wp-json\/wp\/v2\/posts\/111\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/dgp\/wp-json\/wp\/v2\/media\/112"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/dgp\/wp-json\/wp\/v2\/media?parent=111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uoh.cl\/dgp\/wp-json\/wp\/v2\/categories?post=111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uoh.cl\/dgp\/wp-json\/wp\/v2\/tags?post=111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}