
{"id":1810,"date":"2022-12-05T17:06:01","date_gmt":"2022-12-05T20:06:01","guid":{"rendered":"https:\/\/www.uoh.cl\/admision\/2022\/12\/05\/cuestionario-que-mide-riesgos-psicosociales-en-el-trabajo-se-aplicara-durante-diciembre\/"},"modified":"2022-12-07T08:07:14","modified_gmt":"2022-12-07T11:07:14","slug":"cuestionario-que-mide-riesgos-psicosociales-en-el-trabajo-se-aplicara-durante-diciembre","status":"publish","type":"post","link":"https:\/\/www.uoh.cl\/admision\/2022\/12\/05\/cuestionario-que-mide-riesgos-psicosociales-en-el-trabajo-se-aplicara-durante-diciembre\/","title":{"rendered":"Cuestionario que mide riesgos psicosociales en el trabajo se aplicar\u00e1 durante diciembre"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center text-right circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row][vc_column]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/admision\"><span itemprop=\"name\">Admisi\u00f3n UOH<\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Cuestionario que mide riesgos psicosociales en el trabajo se aplicar\u00e1 <\/span><meta itemprop=\"position\" content=\"3\" \/><\/ol><\/div><ul class=\"p-0 list-style-none d-inline-block\"><li class=\"p-0\"><a href=https:\/\/www.uoh.cl\/admision\/category\/institucional\/ class=\"px-1 py-2\">Institucional<\/a><\/li><\/ul><div class=\"date_publish_post\"> \u25cf Lun 05 de Diciembre 2022<\/div><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block title--decorator  big\">Cuestionario que mide riesgos psicosociales en el trabajo se aplicar\u00e1 durante diciembre<\/h1><\/div>[vc_row_inner el_class=&#8221;border-separator m-0&#8243;][vc_column_inner width=&#8221;2\/3&#8243;]<div class=\"author_wp_class\"> Escrito por <span>Universidad de O'Higgins<\/span><\/div>[\/vc_column_inner][vc_column_inner el_class=&#8221;align-items-end-publish&#8221; width=&#8221;1\/3&#8243;]<div class=\"uoh_social_network_component uoh_row col-12 justify-content-end m-0 p-0\"> <div class=\"icon__facebook-share-button\">\n                       <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.uoh.cl\/admision\/2022\/12\/05\/cuestionario-que-mide-riesgos-psicosociales-en-el-trabajo-se-aplicara-durante-diciembre\/\" target=\"_blank\"> <div class=\"icon__facebook-svg\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22.4px\" height=\"48.3px\" viewBox=\"0 0 22.4 48.3\" style=\"overflow:visible;enable-background:new 0 0 22.4 48.3;\" xml:space=\"preserve\">\n                <defs>\n                <\/defs>\n                <path class=\"st0\" d=\"M22.4,15.6h-7.6v-5c0-1.9,1.2-2.3,2.1-2.3c0.9,0,5.4,0,5.4,0V0l-7.4,0C6.6,0,4.8,6.2,4.8,10.1v5.5H0v8.5h4.8\n                    c0,10.9,0,24.1,0,24.1h10c0,0,0-13.3,0-24.1h6.8L22.4,15.6z\"><\/path>\n                <\/svg><\/a><\/div>\n                    <\/div><div class=\"icon__twitter-share-button\">\n                        <div class=\"icon__twitter-svg\"><a target=\"_blank\" href=\"http:\/\/twitter.com\/share?url=https:\/\/www.uoh.cl\/admision\/2022\/12\/05\/cuestionario-que-mide-riesgos-psicosociales-en-el-trabajo-se-aplicara-durante-diciembre\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/a><\/div>\n                        <\/div><div class=\"icon__linkedin-share-button\">\n                        <div class=\"icon__linkedin-svg\">\n                        <a target=\"__blank\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.uoh.cl\/admision\/2022\/12\/05\/cuestionario-que-mide-riesgos-psicosociales-en-el-trabajo-se-aplicara-durante-diciembre\/\"><svg enable-background=\"new 0 0 100 100\" height=\"100px\" id=\"Layer_1\" version=\"1.1\" viewBox=\"0 0 100 100\" width=\"100px\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><circle cx=\"50\" cy=\"50\" fill=\"#ccc\" r=\"45\"\/><g id=\"LinkedIn_1_\"><rect fill=\"#FFFFFF\" height=\"24.361\" width=\"7.69\" x=\"31.271\" y=\"43.569\"\/><path d=\"M59.968,43.334c-4.406,0-7.165,2.387-7.677,4.058v-3.823h-8.636c0.109,2.03,0,24.361,0,24.361h8.636    V54.748c0-0.733-0.034-1.465,0.19-1.991c0.594-1.464,1.869-2.985,4.162-2.985c2.998,0,4.361,2.253,4.361,5.552V67.93h8.721V54.384    C69.726,46.839,65.432,43.334,59.968,43.334z\" fill=\"#FFFFFF\"\/><path d=\"M34.973,32.069c-2.839,0-4.696,1.823-4.696,4.229c0,2.361,1.804,4.224,4.589,4.224h0.054    c2.891,0,4.69-1.869,4.69-4.229C39.555,33.888,37.81,32.069,34.973,32.069z\" fill=\"#FFFFFF\"\/><\/g><\/g><\/svg><\/a><\/div>\n\n            <\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_single_image image=&#8221;15650&#8243; img_size=&#8221;full&#8221;][vc_column_text]\u00a0[\/vc_column_text][vc_column_text]<em>Se trata del ISTAS21, instrumento que permite identificar y medir aquellos factores derivados de la organizaci\u00f3n del trabajo que constituyen un riesgo para la salud.<\/em><\/p>\n<p>[\/vc_column_text][vc_column_text]\u00a0[\/vc_column_text][vc_column_text]Desde el 12 al 16 de diciembre se aplicar\u00e1 al personal acad\u00e9mico y no acad\u00e9mico de nuestra universidad, el cuestionario ISTAS21, instrumento del Protocolo de Vigilancia de Riesgos Psicosociales en el Trabajo y que tiene como objetivo identificar y medir aquellos factores derivados de la organizaci\u00f3n del trabajo que constituyen un riesgo para la salud<\/p>\n<p>\u201cBajo el inter\u00e9s de conocer en qu\u00e9 estado se encuentra el personal de la Universidad de O\u2019Higgins, se iniciar\u00e1 en diciembre la aplicaci\u00f3n del Protocolo de Vigilancia de Riesgos Psicosociales en el Trabajo, instrumento conocido como ISTAS21. El protocolo se traduce en un cuestionario que mide 5 dimensiones\/factores que pueden afectar la salud mental de las y los funcionarios en el trabajo, tales como exigencias psicol\u00f3gicas; trabajo activo y desarrollo de habilidades; apoyo social y calidad de liderazgo; compensaciones; doble presencia\u201d, sostuvo Flavia Mel\u00e9ndez, Prevencionista de Riesgos de la Direcci\u00f3n de Gesti\u00f3n de Personas y miembro del Comit\u00e9 de Vigilancia de Riesgos Psicosociales de la UOH.<\/p>\n<p>La aplicaci\u00f3n del cuestionario estar\u00e1 a cargo del Comit\u00e9 de Vigilancia de Riesgos Psicosociales, conformado por funcionarias y funcionarios designados por la universidad, adem\u00e1s de integrantes del Comit\u00e9 Paritario de Higiene y Seguridad (CPHS). Esta aplicaci\u00f3n ser\u00e1 supervisada por el Instituto de Seguridad Laboral (ISL), organismo administrador de la Ley N\u00b016.744, quien entregar\u00e1 asesor\u00eda t\u00e9cnica especializada.<\/p>\n<p>\u201cEl ISTAS21 fue aplicado en la UOH el a\u00f1o 2018, por lo que en esta nueva instancia estaremos en proceso de reevaluaci\u00f3n. En virtud de aquello, la participaci\u00f3n de todas y todos los funcionarios es fundamental para que la instituci\u00f3n cuente con una imagen clara de la situaci\u00f3n de nuestro personal, en relaci\u00f3n a los riesgos psicosociales del trabajo y los puestos laborales, y con ello orientar la toma de decisiones al respecto\u201d, finaliz\u00f3 Flavia Mel\u00e9ndez.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650255686594{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center text-right p-md-0 pt-5 pb-5&#8243;][vc_column el_class=&#8221;pb-5&#8243;][vc_row_inner el_class=&#8221;pb-5&#8243;][vc_column_inner]<div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0\"><h2 class=\"title title--decorator title--ms d-inline-block\">Te Recomendamos<\/h2><\/div><\/div><div class=\"content-holder\"><div class=\"row  swipper-news-list not--activate-hack \"><div class=\"row -wrapper\"><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/admision\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2026\/04\/Inauguracion-Ano-Academico-2026-6.jpg\" alt=\"Reflexi\u00f3n universitaria: UOH inaugura A\u00f1o Acad\u00e9mico 2026 pensando en los desaf\u00edos de la Educaci\u00f3n Superior\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Mi\u00e9rcoles 29, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/admision\/2026\/04\/29\/reflexion-universitaria-uoh-inaugura-ano-academico-2026-pensando-en-los-desafios-de-la-educacion-superior\/\">\n                                    <h3 class=\"small-space\">Reflexi\u00f3n universitaria: UOH inaugura A\u00f1o Acad\u00e9mico 2026 pensando en los desaf\u00edos de la Educaci\u00f3n Superior<\/h3><\/a>\n\n                                    <p>La ceremonia promovi\u00f3 el an\u00e1lisis acerca de los cambios educativos que se avecinan dentro de los procesos de formaci\u00f3n universitaria ajustados a contextos digitales.   <\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/admision\/2026\/04\/29\/reflexion-universitaria-uoh-inaugura-ano-academico-2026-pensando-en-los-desafios-de-la-educacion-superior\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/admision\/category\/admision\/\">\n                                        Admisi\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2026\/04\/DSC_2709-scaled.jpg\" alt=\"Admisi\u00f3n UOH y Unidad de Bibliotecas convocaron talentos en el D\u00eda del Libro\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/1707;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Lunes 27, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/admision\/2026\/04\/27\/admision-uoh-y-unidad-de-bibliotecas-convocaron-talentos-en-el-dia-del-libro\/\">\n                                    <h3 class=\"small-space\">Admisi\u00f3n UOH y Unidad de Bibliotecas convocaron talentos en el D\u00eda del Libro<\/h3><\/a>\n\n                                    <p>Este primer concurso ten\u00eda como fin vincular a estudiantes de ense\u00f1anza media con la escritura y as\u00ed fomentar la creaci\u00f3n literaria.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/admision\/2026\/04\/27\/admision-uoh-y-unidad-de-bibliotecas-convocaron-talentos-en-el-dia-del-libro\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/admision\/category\/cuech\/\">\n                                        CUECH<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2026\/04\/DSC_2431-scaled.jpg\" alt=\"Universidades estatales sellan hoja de ruta 2030: Red Desarrollo Sustentable entra en fase de consolidaci\u00f3n\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/1707;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Mi\u00e9rcoles 15, Abril<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/admision\/2026\/04\/15\/universidades-estatales-sellan-hoja-de-ruta-2030-red-desarrollo-sustentable-entra-en-fase-de-consolidacion\/\">\n                                    <h3 class=\"small-space\">Universidades estatales sellan hoja de ruta 2030: Red Desarrollo Sustentable entra en fase de consolidaci\u00f3n<\/h3><\/a>\n\n                                    <p>En el Plenario realizado en la Universidad de O'Higgins, los 18 planteles p\u00fablicos definieron sus metas estrat\u00e9gicas para el periodo 2026-2030. El plan priorizar\u00e1 la institucionalizaci\u00f3n de capacidades, un diplomado para organismos p\u00fablicos y la medici\u00f3n de la huella h\u00eddrica en los campus.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/admision\/2026\/04\/15\/universidades-estatales-sellan-hoja-de-ruta-2030-red-desarrollo-sustentable-entra-en-fase-de-consolidacion\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pagination justify-content-center my-5\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/posts\/1810\/\/page\/2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/posts\/1810\/\/page\/3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/posts\/1810\/\/page\/135\">135<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/posts\/1810\/\/page\/2\"><div class=\"icon-pagination-next\"> <?xml version=\"1.0\" ?><svg viewBox=\"0 0 96 96\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><title\/><path d=\"M39.3756,48.0022l30.47-25.39a6.0035,6.0035,0,0,0-7.6878-9.223L26.1563,43.3906a6.0092,6.0092,0,0,0,0,9.2231L62.1578,82.615a6.0035,6.0035,0,0,0,7.6878-9.2231Z\"\/><\/svg> <\/div><\/a><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Se trata del ISTAS21, instrumento que permite identificar y medir aquellos factores derivados de la organizaci\u00f3n del trabajo que constituyen un riesgo para la salud.<\/p>\n","protected":false},"author":34,"featured_media":1859,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucional"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cuestionario que mide riesgos psicosociales en el trabajo se aplicar\u00e1 durante diciembre - Admisi\u00f3n UOH<\/title>\n<meta name=\"description\" content=\"Se trata del ISTAS21, instrumento que permite identificar y medir aquellos factores derivados de la organizaci\u00f3n del trabajo que constituyen un riesgo para la salud.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuestionario que mide riesgos psicosociales en el trabajo se aplicar\u00e1 durante diciembre - Admisi\u00f3n UOH\" \/>\n<meta property=\"og:description\" content=\"Se trata del ISTAS21, instrumento que permite identificar y medir aquellos factores derivados de la organizaci\u00f3n del trabajo que constituyen un riesgo para la salud.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/admision\/2022\/12\/05\/cuestionario-que-mide-riesgos-psicosociales-en-el-trabajo-se-aplicara-durante-diciembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Admisi\u00f3n UOH\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-05T20:06:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-07T11:07:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2022\/12\/Cuestionario-DGP.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Universidad de O&#039;Higgins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Universidad de O&#039;Higgins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uoh.cl\/admision\/2022\/12\/05\/cuestionario-que-mide-riesgos-psicosociales-en-el-trabajo-se-aplicara-durante-diciembre\/\",\"url\":\"https:\/\/www.uoh.cl\/admision\/2022\/12\/05\/cuestionario-que-mide-riesgos-psicosociales-en-el-trabajo-se-aplicara-durante-diciembre\/\",\"name\":\"Cuestionario que mide riesgos psicosociales en el trabajo se aplicar\u00e1 durante diciembre - Admisi\u00f3n UOH\",\"isPartOf\":{\"@id\":\"https:\/\/www.uoh.cl\/admision\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uoh.cl\/admision\/2022\/12\/05\/cuestionario-que-mide-riesgos-psicosociales-en-el-trabajo-se-aplicara-durante-diciembre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uoh.cl\/admision\/2022\/12\/05\/cuestionario-que-mide-riesgos-psicosociales-en-el-trabajo-se-aplicara-durante-diciembre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2022\/12\/Cuestionario-DGP.png\",\"datePublished\":\"2022-12-05T20:06:01+00:00\",\"dateModified\":\"2022-12-07T11:07:14+00:00\",\"author\":{\"@id\":\"https:\/\/www.uoh.cl\/admision\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"description\":\"Se trata del ISTAS21, instrumento que permite identificar y medir aquellos factores derivados de la organizaci\u00f3n del trabajo que constituyen un riesgo para la salud.\",\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uoh.cl\/admision\/2022\/12\/05\/cuestionario-que-mide-riesgos-psicosociales-en-el-trabajo-se-aplicara-durante-diciembre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/admision\/2022\/12\/05\/cuestionario-que-mide-riesgos-psicosociales-en-el-trabajo-se-aplicara-durante-diciembre\/#primaryimage\",\"url\":\"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2022\/12\/Cuestionario-DGP.png\",\"contentUrl\":\"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2022\/12\/Cuestionario-DGP.png\",\"width\":1000,\"height\":1000},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uoh.cl\/admision\/#website\",\"url\":\"https:\/\/www.uoh.cl\/admision\/\",\"name\":\"Admisi\u00f3n UOH\",\"description\":\"Otro sitio de Sitios de Universidad O&#039;higgins\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uoh.cl\/admision\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uoh.cl\/admision\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f\",\"name\":\"Universidad de O'Higgins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.uoh.cl\/admision\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"caption\":\"Universidad de O'Higgins\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuestionario que mide riesgos psicosociales en el trabajo se aplicar\u00e1 durante diciembre - Admisi\u00f3n UOH","description":"Se trata del ISTAS21, instrumento que permite identificar y medir aquellos factores derivados de la organizaci\u00f3n del trabajo que constituyen un riesgo para la salud.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Cuestionario que mide riesgos psicosociales en el trabajo se aplicar\u00e1 durante diciembre - Admisi\u00f3n UOH","og_description":"Se trata del ISTAS21, instrumento que permite identificar y medir aquellos factores derivados de la organizaci\u00f3n del trabajo que constituyen un riesgo para la salud.","og_url":"https:\/\/www.uoh.cl\/admision\/2022\/12\/05\/cuestionario-que-mide-riesgos-psicosociales-en-el-trabajo-se-aplicara-durante-diciembre\/","og_site_name":"Admisi\u00f3n UOH","article_published_time":"2022-12-05T20:06:01+00:00","article_modified_time":"2022-12-07T11:07:14+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2022\/12\/Cuestionario-DGP.png","type":"image\/png"}],"author":"Universidad de O'Higgins","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Universidad de O'Higgins","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/admision\/2022\/12\/05\/cuestionario-que-mide-riesgos-psicosociales-en-el-trabajo-se-aplicara-durante-diciembre\/","url":"https:\/\/www.uoh.cl\/admision\/2022\/12\/05\/cuestionario-que-mide-riesgos-psicosociales-en-el-trabajo-se-aplicara-durante-diciembre\/","name":"Cuestionario que mide riesgos psicosociales en el trabajo se aplicar\u00e1 durante diciembre - Admisi\u00f3n UOH","isPartOf":{"@id":"https:\/\/www.uoh.cl\/admision\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uoh.cl\/admision\/2022\/12\/05\/cuestionario-que-mide-riesgos-psicosociales-en-el-trabajo-se-aplicara-durante-diciembre\/#primaryimage"},"image":{"@id":"https:\/\/www.uoh.cl\/admision\/2022\/12\/05\/cuestionario-que-mide-riesgos-psicosociales-en-el-trabajo-se-aplicara-durante-diciembre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2022\/12\/Cuestionario-DGP.png","datePublished":"2022-12-05T20:06:01+00:00","dateModified":"2022-12-07T11:07:14+00:00","author":{"@id":"https:\/\/www.uoh.cl\/admision\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"description":"Se trata del ISTAS21, instrumento que permite identificar y medir aquellos factores derivados de la organizaci\u00f3n del trabajo que constituyen un riesgo para la salud.","inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/admision\/2022\/12\/05\/cuestionario-que-mide-riesgos-psicosociales-en-el-trabajo-se-aplicara-durante-diciembre\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/admision\/2022\/12\/05\/cuestionario-que-mide-riesgos-psicosociales-en-el-trabajo-se-aplicara-durante-diciembre\/#primaryimage","url":"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2022\/12\/Cuestionario-DGP.png","contentUrl":"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2022\/12\/Cuestionario-DGP.png","width":1000,"height":1000},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/admision\/#website","url":"https:\/\/www.uoh.cl\/admision\/","name":"Admisi\u00f3n UOH","description":"Otro sitio de Sitios de Universidad O&#039;higgins","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/admision\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/www.uoh.cl\/admision\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f","name":"Universidad de O'Higgins","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/admision\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","caption":"Universidad de O'Higgins"}}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/posts\/1810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/comments?post=1810"}],"version-history":[{"count":2,"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/posts\/1810\/revisions"}],"predecessor-version":[{"id":1826,"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/posts\/1810\/revisions\/1826"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/media\/1859"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/media?parent=1810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/categories?post=1810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/tags?post=1810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}