
{"id":1604,"date":"2022-11-13T19:13:13","date_gmt":"2022-11-13T22:13:13","guid":{"rendered":"https:\/\/www.uoh.cl\/admision\/2022\/11\/13\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\/"},"modified":"2022-11-13T19:13:13","modified_gmt":"2022-11-13T22:13:13","slug":"pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais","status":"publish","type":"post","link":"https:\/\/www.uoh.cl\/admision\/2022\/11\/13\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\/","title":{"rendered":"Pedagog\u00eda en Ciencias Naturales: Potenciando la educaci\u00f3n cient\u00edfica del pa\u00eds"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center text-right circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row][vc_column]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/admision\"><span itemprop=\"name\">Admisi\u00f3n UOH<\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Pedagog\u00eda en Ciencias Naturales: Potenciando la educaci\u00f3n cient\u00edfica del pa\u00eds <\/span><meta itemprop=\"position\" content=\"3\" \/><\/ol><\/div><ul class=\"p-0 list-style-none d-inline-block\"><li class=\"p-0\"><a href=https:\/\/www.uoh.cl\/admision\/category\/educacion\/ class=\"px-1 py-2\">Educaci\u00f3n<\/a><\/li><\/ul><div class=\"date_publish_post\"> \u25cf Dom 13 de Noviembre 2022<\/div><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block title--decorator  big\">Pedagog\u00eda en Ciencias Naturales: Potenciando la educaci\u00f3n cient\u00edfica del pa\u00eds<\/h1><\/div>[vc_row_inner el_class=&#8221;border-separator m-0&#8243;][vc_column_inner width=&#8221;2\/3&#8243;]<div class=\"author_wp_class\"> Escrito por <span>Universidad de O'Higgins<\/span><\/div>[\/vc_column_inner][vc_column_inner el_class=&#8221;align-items-end-publish&#8221; width=&#8221;1\/3&#8243;]<div class=\"uoh_social_network_component uoh_row col-12 justify-content-end m-0 p-0\"> <div class=\"icon__facebook-share-button\">\n                       <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.uoh.cl\/admision\/2022\/11\/13\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\/\" target=\"_blank\"> <div class=\"icon__facebook-svg\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22.4px\" height=\"48.3px\" viewBox=\"0 0 22.4 48.3\" style=\"overflow:visible;enable-background:new 0 0 22.4 48.3;\" xml:space=\"preserve\">\n                <defs>\n                <\/defs>\n                <path class=\"st0\" d=\"M22.4,15.6h-7.6v-5c0-1.9,1.2-2.3,2.1-2.3c0.9,0,5.4,0,5.4,0V0l-7.4,0C6.6,0,4.8,6.2,4.8,10.1v5.5H0v8.5h4.8\n                    c0,10.9,0,24.1,0,24.1h10c0,0,0-13.3,0-24.1h6.8L22.4,15.6z\"><\/path>\n                <\/svg><\/a><\/div>\n                    <\/div><div class=\"icon__twitter-share-button\">\n                        <div class=\"icon__twitter-svg\"><a target=\"_blank\" href=\"http:\/\/twitter.com\/share?url=https:\/\/www.uoh.cl\/admision\/2022\/11\/13\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/a><\/div>\n                        <\/div><div class=\"icon__linkedin-share-button\">\n                        <div class=\"icon__linkedin-svg\">\n                        <a target=\"__blank\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.uoh.cl\/admision\/2022\/11\/13\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\/\"><svg enable-background=\"new 0 0 100 100\" height=\"100px\" id=\"Layer_1\" version=\"1.1\" viewBox=\"0 0 100 100\" width=\"100px\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><circle cx=\"50\" cy=\"50\" fill=\"#ccc\" r=\"45\"\/><g id=\"LinkedIn_1_\"><rect fill=\"#FFFFFF\" height=\"24.361\" width=\"7.69\" x=\"31.271\" y=\"43.569\"\/><path d=\"M59.968,43.334c-4.406,0-7.165,2.387-7.677,4.058v-3.823h-8.636c0.109,2.03,0,24.361,0,24.361h8.636    V54.748c0-0.733-0.034-1.465,0.19-1.991c0.594-1.464,1.869-2.985,4.162-2.985c2.998,0,4.361,2.253,4.361,5.552V67.93h8.721V54.384    C69.726,46.839,65.432,43.334,59.968,43.334z\" fill=\"#FFFFFF\"\/><path d=\"M34.973,32.069c-2.839,0-4.696,1.823-4.696,4.229c0,2.361,1.804,4.224,4.589,4.224h0.054    c2.891,0,4.69-1.869,4.69-4.229C39.555,33.888,37.81,32.069,34.973,32.069z\" fill=\"#FFFFFF\"\/><\/g><\/g><\/svg><\/a><\/div>\n\n            <\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_single_image image=&#8221;14077&#8243; img_size=&#8221;large&#8221;][vc_column_text][\/vc_column_text][vc_column_text]<\/p>\n<ul style=\"font-weight: 400\">\n<li><em>La carrera de la Universidad Estatal de O\u2019Higgins tiene un enfoque integrador de las disciplinas cient\u00edficas.<\/em><\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"font-weight: 400\">Pedagog\u00eda en Ciencias Naturales con menciones es -en la Universidad Estatal de O\u2019Higgins (UOH)- una carrera pionera, que cambi\u00f3 la forma en c\u00f3mo nos acercamos a la ense\u00f1anza de las ciencias naturales. Un elemento fundamental es su enfoque integrador de las disciplinas cient\u00edficas, que son abordadas en gran parte del plan de estudios a trav\u00e9s de asignaturas que analizan fen\u00f3menos naturales y tem\u00e1ticas como la biolog\u00eda, f\u00edsica, qu\u00edmica y otras ciencias naturales, fomentando una comprensi\u00f3n unificada del saber cient\u00edfico.<\/p>\n<p style=\"font-weight: 400\">&#8220;Tenemos varios objetivos sobre la mesa. Ya contamos con nuestro primer proceso de acreditaci\u00f3n y estamos esperando la respuesta de la Comisi\u00f3n Nacional de Acreditaci\u00f3n. Hacia finales del 2024, deber\u00edamos tener los\/as primeros\/as egresados\/as, por lo que estamos en proceso de consolidaci\u00f3n para contar con nuestros\/as primeros\/as titulados\/as. Otro desaf\u00edo es atraer muchos m\u00e1s estudiantes, ya que es una tendencia en carreras de pedagog\u00edas cient\u00edficas y tenemos el respaldo de nuestras autoridades universitarias&#8221;, apunta la jefa de carrera de Pedagog\u00eda en Ciencias Naturales, Alejandra Rojas.<\/p>\n<p style=\"font-weight: 400\">La carrera cuenta con un tronco de asignaturas enfocadas en el desarrollo del pensamiento cient\u00edfico y de habilidades en este \u00e1mbito, que atraviesan el proceso formativo y sustentan el enfoque integrador.<\/p>\n<p style=\"font-weight: 400\">&#8220;Contamos con muchas salidas pedag\u00f3gicas, lo que se ha transformado en un sello de la carrera, siendo la naturaleza un escenario de aprendizaje. La Regi\u00f3n de O&#8217;Higgins tiene importantes problemas socio-ambientales que afectan a sus comunidades, el uso de agro-t\u00f3xicos y la sequ\u00eda, entre otros. En la carrera, creemos que trabajar en base a estas problem\u00e1ticas involucra a la ciencia de manera importante, por lo que habr\u00e1 profesores y profesoras que realicen buenas clases e incorporen estas tem\u00e1ticas en el aula&#8221;, agrega la jefa de carrera.<\/p>\n<p style=\"font-weight: 400\">Junto con esto, la carrera formar\u00e1 profesionales capaces de asumir un rol protag\u00f3nico m\u00e1s all\u00e1 del aula, en contacto con la comunidad educativa a trav\u00e9s del trabajo en proyectos y de la conexi\u00f3n entre el saber cient\u00edfico, la formaci\u00f3n ciudadana y los desaf\u00edos medioambientales locales.<\/p>\n<p style=\"font-weight: 400\">&#8220;Los\/as egresados\/as podr\u00e1n hacer clases para estudiantes entre s\u00e9ptimo b\u00e1sico y cuarto medio, con la opci\u00f3n de hacer electivos en Qu\u00edmica, F\u00edsica y Biolog\u00eda, adem\u00e1s de otras opciones como museos, universidades y proyectos cient\u00edfico-medioambientales. La empleabilidad de esta carrera debe bordear el 100% y, seguramente muchos de nuestros estudiantes, incluso antes de egresar, van a estar trabajando. Esa es una de nuestras proyecciones&#8221;, finaliza Alejandra Rojas.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650255686594{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center text-right p-md-0 pt-5 pb-5&#8243;][vc_column el_class=&#8221;pb-5&#8243;][vc_row_inner el_class=&#8221;pb-5&#8243;][vc_column_inner]<div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0\"><h2 class=\"title title--decorator title--ms d-inline-block\">Te Recomendamos<\/h2><\/div><\/div><div class=\"content-holder\"><div class=\"row  swipper-news-list not--activate-hack \"><div class=\"row -wrapper\"><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/admision\/category\/admision\/\">\n                                        Admisi\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2026\/08\/Torneo-Delivera-2026-138.jpg\" alt=\"En la UOH se escogi\u00f3 al ganador regional del Torneo Delibera\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Lunes 31, Agosto<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/admision\/2026\/08\/31\/en-la-uoh-se-escogio-al-ganador-regional-del-torneo-delibera\/\">\n                                    <h3 class=\"small-space\">En la UOH se escogi\u00f3 al ganador regional del Torneo Delibera<\/h3><\/a>\n\n                                    <p>Estudiantes del Colegio Ena Bellemans Montti representar\u00e1n a la zona en el campeonato nacional que se desarrollar\u00e1 en noviembre en el Congreso Nacional.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/admision\/2026\/08\/31\/en-la-uoh-se-escogio-al-ganador-regional-del-torneo-delibera\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/admision\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2026\/08\/Pukara-2.jpeg\" alt=\"Hist\u00f3rico acuerdo permitir\u00e1 a la UOH proteger y poner en valor el Pukar\u00e1 de La Compa\u00f1\u00eda\" style=\"--smush-placeholder-width: 1600px; --smush-placeholder-aspect-ratio: 1600\/1066;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Viernes 28, Agosto<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/admision\/2026\/08\/28\/historico-acuerdo-permitira-a-la-uoh-proteger-y-poner-en-valor-el-pukara-de-la-compania\/\">\n                                    <h3 class=\"small-space\">Hist\u00f3rico acuerdo permitir\u00e1 a la UOH proteger y poner en valor el Pukar\u00e1 de La Compa\u00f1\u00eda<\/h3><\/a>\n\n                                    <p>Acuerdo impulsado por el CDE permitir\u00e1 que uno de los sitios arqueol\u00f3gicos m\u00e1s importantes de Chile quede bajo el resguardo de una universidad estatal y se transforme en un espacio permanente para la investigaci\u00f3n cient\u00edfica, la educaci\u00f3n patrimonial y el desarrollo cultural de la Regi\u00f3n de O\u2019Higgins.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/admision\/2026\/08\/28\/historico-acuerdo-permitira-a-la-uoh-proteger-y-poner-en-valor-el-pukara-de-la-compania\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/admision\/category\/admision\/\">\n                                        Admisi\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2026\/08\/IMG_7106-scaled.jpg\" alt=\"M\u00e1s de 1.600 estudiantes de O\u2019Higgins viven experiencia de exploraci\u00f3n vocacional en un nuevo Puertas Abiertas de Campus Colchagua\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/1707;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Viernes 14, Agosto<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/admision\/2026\/08\/14\/mas-de-1-600-estudiantes-de-ohiggins-viven-experiencia-de-exploracion-vocacional-en-un-nuevo-puertas-abiertas-de-campus-colchagua\/\">\n                                    <h3 class=\"small-space\">M\u00e1s de 1.600 estudiantes de O\u2019Higgins viven experiencia de exploraci\u00f3n vocacional en un nuevo Puertas Abiertas de Campus Colchagua<\/h3><\/a>\n\n                                    <p>La visita a las instalaciones de la Escuela de Ciencias Agroalimentarias, Animales y Ambientales, ubicadas en San Fernando, const\u00f3 de recorridos guiados por instalaciones y laboratorios, charlas y experiencias de laboratorio.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/admision\/2026\/08\/14\/mas-de-1-600-estudiantes-de-ohiggins-viven-experiencia-de-exploracion-vocacional-en-un-nuevo-puertas-abiertas-de-campus-colchagua\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pagination justify-content-center my-5\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/posts\/1604\/\/page\/2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/posts\/1604\/\/page\/3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/posts\/1604\/\/page\/139\">139<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/posts\/1604\/\/page\/2\"><div class=\"icon-pagination-next\"> <?xml version=\"1.0\" ?><svg viewBox=\"0 0 96 96\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><title\/><path d=\"M39.3756,48.0022l30.47-25.39a6.0035,6.0035,0,0,0-7.6878-9.223L26.1563,43.3906a6.0092,6.0092,0,0,0,0,9.2231L62.1578,82.615a6.0035,6.0035,0,0,0,7.6878-9.2231Z\"\/><\/svg> <\/div><\/a><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La carrera de la Universidad Estatal de O\u2019Higgins tiene un enfoque integrador de las disciplinas cient\u00edficas.<\/p>\n","protected":false},"author":34,"featured_media":1605,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[28],"tags":[],"class_list":["post-1604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pedagog\u00eda en Ciencias Naturales: Potenciando la educaci\u00f3n cient\u00edfica del pa\u00eds - Admisi\u00f3n UOH<\/title>\n<meta name=\"description\" content=\"La carrera de la Universidad Estatal de O\u2019Higgins tiene un enfoque integrador de las disciplinas cient\u00edficas.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pedagog\u00eda en Ciencias Naturales: Potenciando la educaci\u00f3n cient\u00edfica del pa\u00eds - Admisi\u00f3n UOH\" \/>\n<meta property=\"og:description\" content=\"La carrera de la Universidad Estatal de O\u2019Higgins tiene un enfoque integrador de las disciplinas cient\u00edficas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/admision\/2022\/11\/13\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\/\" \/>\n<meta property=\"og:site_name\" content=\"Admisi\u00f3n UOH\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-13T22:13:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2022\/11\/Laboratorio-Naturales-2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"925\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Universidad de O&#039;Higgins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Universidad de O&#039;Higgins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/2022\\\/11\\\/13\\\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/2022\\\/11\\\/13\\\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\\\/\"},\"author\":{\"name\":\"Universidad de O'Higgins\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/#\\\/schema\\\/person\\\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"headline\":\"Pedagog\u00eda en Ciencias Naturales: Potenciando la educaci\u00f3n cient\u00edfica del pa\u00eds\",\"datePublished\":\"2022-11-13T22:13:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/2022\\\/11\\\/13\\\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\\\/\"},\"wordCount\":689,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/2022\\\/11\\\/13\\\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/Laboratorio-Naturales-2-1.jpg\",\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/2022\\\/11\\\/13\\\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/2022\\\/11\\\/13\\\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\\\/\",\"url\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/2022\\\/11\\\/13\\\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\\\/\",\"name\":\"Pedagog\u00eda en Ciencias Naturales: Potenciando la educaci\u00f3n cient\u00edfica del pa\u00eds - Admisi\u00f3n UOH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/2022\\\/11\\\/13\\\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/2022\\\/11\\\/13\\\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/Laboratorio-Naturales-2-1.jpg\",\"datePublished\":\"2022-11-13T22:13:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/#\\\/schema\\\/person\\\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"description\":\"La carrera de la Universidad Estatal de O\u2019Higgins tiene un enfoque integrador de las disciplinas cient\u00edficas.\",\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/2022\\\/11\\\/13\\\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/2022\\\/11\\\/13\\\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/Laboratorio-Naturales-2-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/Laboratorio-Naturales-2-1.jpg\",\"width\":1500,\"height\":925},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/#website\",\"url\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/\",\"name\":\"Admisi\u00f3n UOH\",\"description\":\"Otro sitio de Sitios de Universidad O&#039;higgins\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/#\\\/schema\\\/person\\\/ea242e676c7d6d7e46fc8b9e39486c4f\",\"name\":\"Universidad de O'Higgins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"caption\":\"Universidad de O'Higgins\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pedagog\u00eda en Ciencias Naturales: Potenciando la educaci\u00f3n cient\u00edfica del pa\u00eds - Admisi\u00f3n UOH","description":"La carrera de la Universidad Estatal de O\u2019Higgins tiene un enfoque integrador de las disciplinas cient\u00edficas.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Pedagog\u00eda en Ciencias Naturales: Potenciando la educaci\u00f3n cient\u00edfica del pa\u00eds - Admisi\u00f3n UOH","og_description":"La carrera de la Universidad Estatal de O\u2019Higgins tiene un enfoque integrador de las disciplinas cient\u00edficas.","og_url":"https:\/\/www.uoh.cl\/admision\/2022\/11\/13\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\/","og_site_name":"Admisi\u00f3n UOH","article_published_time":"2022-11-13T22:13:13+00:00","og_image":[{"width":1500,"height":925,"url":"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2022\/11\/Laboratorio-Naturales-2-1.jpg","type":"image\/jpeg"}],"author":"Universidad de O'Higgins","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Universidad de O'Higgins","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uoh.cl\/admision\/2022\/11\/13\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\/#article","isPartOf":{"@id":"https:\/\/www.uoh.cl\/admision\/2022\/11\/13\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\/"},"author":{"name":"Universidad de O'Higgins","@id":"https:\/\/www.uoh.cl\/admision\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"headline":"Pedagog\u00eda en Ciencias Naturales: Potenciando la educaci\u00f3n cient\u00edfica del pa\u00eds","datePublished":"2022-11-13T22:13:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uoh.cl\/admision\/2022\/11\/13\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\/"},"wordCount":689,"commentCount":0,"image":{"@id":"https:\/\/www.uoh.cl\/admision\/2022\/11\/13\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2022\/11\/Laboratorio-Naturales-2-1.jpg","articleSection":["Educaci\u00f3n"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.uoh.cl\/admision\/2022\/11\/13\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/admision\/2022\/11\/13\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\/","url":"https:\/\/www.uoh.cl\/admision\/2022\/11\/13\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\/","name":"Pedagog\u00eda en Ciencias Naturales: Potenciando la educaci\u00f3n cient\u00edfica del pa\u00eds - Admisi\u00f3n UOH","isPartOf":{"@id":"https:\/\/www.uoh.cl\/admision\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uoh.cl\/admision\/2022\/11\/13\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\/#primaryimage"},"image":{"@id":"https:\/\/www.uoh.cl\/admision\/2022\/11\/13\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2022\/11\/Laboratorio-Naturales-2-1.jpg","datePublished":"2022-11-13T22:13:13+00:00","author":{"@id":"https:\/\/www.uoh.cl\/admision\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"description":"La carrera de la Universidad Estatal de O\u2019Higgins tiene un enfoque integrador de las disciplinas cient\u00edficas.","inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/admision\/2022\/11\/13\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/admision\/2022\/11\/13\/pedagogia-en-ciencias-naturales-potenciando-la-educacion-cientifica-del-pais\/#primaryimage","url":"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2022\/11\/Laboratorio-Naturales-2-1.jpg","contentUrl":"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2022\/11\/Laboratorio-Naturales-2-1.jpg","width":1500,"height":925},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/admision\/#website","url":"https:\/\/www.uoh.cl\/admision\/","name":"Admisi\u00f3n UOH","description":"Otro sitio de Sitios de Universidad O&#039;higgins","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/admision\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/www.uoh.cl\/admision\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f","name":"Universidad de O'Higgins","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","caption":"Universidad de O'Higgins"}}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/posts\/1604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/comments?post=1604"}],"version-history":[{"count":0,"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/posts\/1604\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/media\/1605"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/media?parent=1604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/categories?post=1604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/tags?post=1604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}