
{"id":1087,"date":"2022-09-27T11:45:27","date_gmt":"2022-09-27T14:45:27","guid":{"rendered":"https:\/\/www.uoh.cl\/admision\/2022\/09\/27\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\/"},"modified":"2022-09-27T11:58:47","modified_gmt":"2022-09-27T14:58:47","slug":"uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023","status":"publish","type":"post","link":"https:\/\/www.uoh.cl\/admision\/2022\/09\/27\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\/","title":{"rendered":"UOH realiza \u201cPuertas Abiertas\u201d con nueva oferta acad\u00e9mica de cara al Proceso de Admisi\u00f3n 2023"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#8221;container mx-auto align-items-center text-right circle&#8211;pattern&#8221; css=&#8221;.vc_custom_1648956589196{padding-top: 3rem !important;}&#8221;][vc_row][vc_column]<div class=\"breadcrumb\"><ol itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"http:\/\/www.uoh.cl\"><span itemprop=\"name\">Inicio<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/www.uoh.cl\/admision\"><span itemprop=\"name\">Admisi\u00f3n UOH<\/span><\/a><meta itemprop=\"position\" content=\"2\" \/><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">UOH realiza \u201cPuertas Abiertas\u201d con nueva oferta acad\u00e9mica de cara <\/span><meta itemprop=\"position\" content=\"3\" \/><\/ol><\/div><ul class=\"p-0 list-style-none d-inline-block\"><li class=\"p-0\"><a href=https:\/\/www.uoh.cl\/admision\/category\/admision-uoh\/ class=\"px-1 py-2\">Admisi\u00f3n UOH<\/a><\/li><\/ul><div class=\"date_publish_post\"> \u25cf Mar 27 de Septiembre 2022<\/div><div class=\"uoh_title_component-container\"><h1 class=\"title title--ms d-inline-block title--decorator  big\">UOH realiza \u201cPuertas Abiertas\u201d con nueva oferta acad\u00e9mica de cara al Proceso de Admisi\u00f3n 2023<\/h1><\/div>[vc_row_inner el_class=&#8221;border-separator m-0&#8243;][vc_column_inner width=&#8221;2\/3&#8243;]<div class=\"author_wp_class\"> Escrito por <span>Universidad de O'Higgins<\/span><\/div>[\/vc_column_inner][vc_column_inner el_class=&#8221;align-items-end-publish&#8221; width=&#8221;1\/3&#8243;]<div class=\"uoh_social_network_component uoh_row col-12 justify-content-end m-0 p-0\"> <div class=\"icon__facebook-share-button\">\n                       <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.uoh.cl\/admision\/2022\/09\/27\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\/\" target=\"_blank\"> <div class=\"icon__facebook-svg\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22.4px\" height=\"48.3px\" viewBox=\"0 0 22.4 48.3\" style=\"overflow:visible;enable-background:new 0 0 22.4 48.3;\" xml:space=\"preserve\">\n                <defs>\n                <\/defs>\n                <path class=\"st0\" d=\"M22.4,15.6h-7.6v-5c0-1.9,1.2-2.3,2.1-2.3c0.9,0,5.4,0,5.4,0V0l-7.4,0C6.6,0,4.8,6.2,4.8,10.1v5.5H0v8.5h4.8\n                    c0,10.9,0,24.1,0,24.1h10c0,0,0-13.3,0-24.1h6.8L22.4,15.6z\"><\/path>\n                <\/svg><\/a><\/div>\n                    <\/div><div class=\"icon__twitter-share-button\">\n                        <div class=\"icon__twitter-svg\"><a target=\"_blank\" href=\"http:\/\/twitter.com\/share?url=https:\/\/www.uoh.cl\/admision\/2022\/09\/27\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/a><\/div>\n                        <\/div><div class=\"icon__linkedin-share-button\">\n                        <div class=\"icon__linkedin-svg\">\n                        <a target=\"__blank\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/www.uoh.cl\/admision\/2022\/09\/27\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\/\"><svg enable-background=\"new 0 0 100 100\" height=\"100px\" id=\"Layer_1\" version=\"1.1\" viewBox=\"0 0 100 100\" width=\"100px\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><circle cx=\"50\" cy=\"50\" fill=\"#ccc\" r=\"45\"\/><g id=\"LinkedIn_1_\"><rect fill=\"#FFFFFF\" height=\"24.361\" width=\"7.69\" x=\"31.271\" y=\"43.569\"\/><path d=\"M59.968,43.334c-4.406,0-7.165,2.387-7.677,4.058v-3.823h-8.636c0.109,2.03,0,24.361,0,24.361h8.636    V54.748c0-0.733-0.034-1.465,0.19-1.991c0.594-1.464,1.869-2.985,4.162-2.985c2.998,0,4.361,2.253,4.361,5.552V67.93h8.721V54.384    C69.726,46.839,65.432,43.334,59.968,43.334z\" fill=\"#FFFFFF\"\/><path d=\"M34.973,32.069c-2.839,0-4.696,1.823-4.696,4.229c0,2.361,1.804,4.224,4.589,4.224h0.054    c2.891,0,4.69-1.869,4.69-4.229C39.555,33.888,37.81,32.069,34.973,32.069z\" fill=\"#FFFFFF\"\/><\/g><\/g><\/svg><\/a><\/div>\n\n            <\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_single_image image=&#8221;10628&#8243; img_size=&#8221;large&#8221;][vc_column_text]\u00a0[\/vc_column_text][vc_column_text]<em>Cuatro nuevas carreras de pregrado se suman a la oferta de la Estatal de O\u2019Higgins el pr\u00f3ximo a\u00f1o. <\/em>[\/vc_column_text][vc_column_text]\u00a0[\/vc_column_text][vc_column_text]Entre el 27 y 29 de septiembre, la UOH retoma su tradicional \u201cPuertas Abiertas\u201d presencial, instancia que permite que alumnas y alumnos que cursan sus \u00faltimos a\u00f1os de ense\u00f1anza media, conozcan las instalaciones de los campus Rancagua y Colchagua, y se puedan interiorizar de las actuales 23 carreras de pregrado y las nuevas cuatro carreras que se suman: Nutrici\u00f3n y Diet\u00e9tica, Kinesiolog\u00eda, Tecnolog\u00eda M\u00e9dica y Contador Auditor (de las escuelas de Salud y Ciencias Sociales)<\/p>\n<p>\u201cLa UOH vuelve a abrir sus puertas para que los estudiantes de diversos colegios de la regi\u00f3n vengan a informarse de las carreras vigentes y las nuevas carreras que comienzan el 2023. Durante tres d\u00edas, los\/as interesados\/as podr\u00e1n acercarse para recibir toda la informaci\u00f3n relativa al proceso general de postulaci\u00f3n y las v\u00edas de Admisi\u00f3n Especial. Es importante dar a conocer las diferentes maneras de ingresar a nuestra universidad. Nuestro llamado es que se acerquen para conocer cu\u00e1les son los detalles de todos los pasos que tienen que seguir\u201d, coment\u00f3 el Vicerrector Acad\u00e9mico de la Universidad de O\u2019Higgins, Marcello Visconti.<\/p>\n<p>Sobre las novedades del proceso de cara al pr\u00f3ximo a\u00f1o, Visconti apunt\u00f3 que \u201cnuestra oferta pasa a contar con 27 carreras de pregrado que se distribuyen en siete especialidades en Educaci\u00f3n, seis en Ingenier\u00eda, seis en Salud, tres en Ciencias Agroalimentarias, Animales y Ambientales y cinco en Ciencias Sociales, adem\u00e1s, de dar comienzo a los primeros mag\u00edsteres de continuaci\u00f3n en Ingenier\u00eda, lo que permite seguir estudiando de manera articulada para aquellos que est\u00e1n terminando sus estudios de Ingenier\u00eda Civil. Todo esto, nos da mucha alegr\u00eda y orgullo de c\u00f3mo ha crecido nuestra instituci\u00f3n\u201d.<\/p>\n<p>A mediados de este a\u00f1o 2022, la UOH titul\u00f3 a sus primeros 147 profesionales de las primeras doce carreras que completaron su primer ciclo formativo, lo cual es uno de los grandes hitos de la instituci\u00f3n. Para el pr\u00f3ximo a\u00f1o, la UOH superar\u00e1 los seis mil estudiantes matriculados, lo cual, para Marcello Visconti, \u201cnos hace ser una universidad plenamente consolidada y estamos empezando a cosechar todo lo sembrado en estos siete a\u00f1os. Tenemos un compromiso con la regi\u00f3n, el que parti\u00f3 como un sue\u00f1o durante muchas d\u00e9cadas, el cual, ahora es una realidad concreta con estos n\u00fameros que reflejan el desarrollo institucional y que seguir\u00e1n teniendo posibilidades de m\u00e1s carreras de pregrado y programas de postgrado\u201d.<\/p>\n<p><strong><img decoding=\"async\" class=\"alignnone wp-image-10632 size-large lazyload\" data-src=\"https:\/\/www.uoh.cl\/wp-content\/uploads\/2022\/09\/Puertas-abiertas-2022-9-1024x659.jpg\" alt=\"Puertas Abiertas 2022\" width=\"1024\" height=\"659\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/659;\" \/><\/strong><\/p>\n<p><strong>Nuevas carreras<\/strong><\/p>\n<p>En junio pasado, el Consejo Acad\u00e9mico aprob\u00f3 cuatro nuevas carreras de pregrado.<\/p>\n<p>La carrera de Nutrici\u00f3n y Diet\u00e9tica va de la mano con las nuevas problem\u00e1ticas de sobre-nutrici\u00f3n que ayudan al desarrollo de enfermedades cr\u00f3nicas no transmisibles tales como obesidad, hipertensi\u00f3n, diabetes y las enfermedades cardiovasculares, las que es necesario enfrentar con una mirada distinta y enfocada en la realidad global y regional.<\/p>\n<p>Asimismo, Kinesiolog\u00eda y Tecnolog\u00eda M\u00e9dica, tienen en com\u00fan la necesidad constante de profesionales en dichas \u00e1reas de la salud, tanto a nivel de la Regi\u00f3n de O\u2019Higgins como en la realidad pa\u00eds.<\/p>\n<p>Por su parte, Contador Auditor busca desarrollar una mirada cr\u00edtica y constructiva en la gesti\u00f3n de los procesos m\u00e1s relevantes de las organizaciones donde se enfatizar\u00e1 en generar, analizar, presentar y emitir opini\u00f3n sobre informes contables financieros de las organizaciones basados en las normas internacionales de contabilidad.<\/p>\n<p><strong>Programa de Mag\u00edster<\/strong><\/p>\n<p>Este 2022 la UOH comenz\u00f3 con sus programas de mag\u00edsteres de continuaci\u00f3n en Ciencias de la Ingenier\u00eda y en Biotecnolog\u00eda, los cuales se suman al de Artes Audiovisuales, que ya marcha en su tercer a\u00f1o de vida.<\/p>\n<p>El mag\u00edster en Ciencias de la Ingenier\u00eda, el que cuenta con cuatro menciones: F\u00edsica y Mec\u00e1nica Aplicada; El\u00e9ctrica; Gesti\u00f3n de Operaciones y Modelamiento de Inteligencia Artificial. Por su parte, el Mag\u00edster en Biotecnolog\u00eda estar\u00e1 disponible desde el primer semestre de 2023, con 12 vacantes, ambos dirigidos a profesionales del \u00e1rea y estudiantes de Ingenier\u00eda Civil UOH.[\/vc_column_text][vc_column_text]<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1650255686594{background-color: #f6faff !important;}&#8221; el_class=&#8221;p-md-0 pt-md-5&#8243;][vc_row el_class=&#8221;container mx-auto align-items-center text-right p-md-0 pt-5 pb-5&#8243;][vc_column el_class=&#8221;pb-5&#8243;][vc_row_inner el_class=&#8221;pb-5&#8243;][vc_column_inner]<div class=\"row m-0 p-0\"><div class=\"col-12 col-md-9 pt-5 pt-md-0\"><h2 class=\"title title--decorator title--ms d-inline-block\">Te Recomendamos<\/h2><\/div><\/div><div class=\"content-holder\"><div class=\"row  swipper-news-list not--activate-hack \"><div class=\"row -wrapper\"><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/admision\/category\/admision\/\">\n                                        Admisi\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2026\/08\/Torneo-Delivera-2026-138.jpg\" alt=\"En la UOH se escogi\u00f3 al ganador regional del Torneo Delibera\" style=\"--smush-placeholder-width: 1500px; --smush-placeholder-aspect-ratio: 1500\/1000;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Lunes 31, Agosto<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/admision\/2026\/08\/31\/en-la-uoh-se-escogio-al-ganador-regional-del-torneo-delibera\/\">\n                                    <h3 class=\"small-space\">En la UOH se escogi\u00f3 al ganador regional del Torneo Delibera<\/h3><\/a>\n\n                                    <p>Estudiantes del Colegio Ena Bellemans Montti representar\u00e1n a la zona en el campeonato nacional que se desarrollar\u00e1 en noviembre en el Congreso Nacional.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/admision\/2026\/08\/31\/en-la-uoh-se-escogio-al-ganador-regional-del-torneo-delibera\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/admision\/category\/institucional\/\">\n                                        Institucional<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2026\/08\/Pukara-2.jpeg\" alt=\"Hist\u00f3rico acuerdo permitir\u00e1 a la UOH proteger y poner en valor el Pukar\u00e1 de La Compa\u00f1\u00eda\" style=\"--smush-placeholder-width: 1600px; --smush-placeholder-aspect-ratio: 1600\/1066;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Viernes 28, Agosto<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/admision\/2026\/08\/28\/historico-acuerdo-permitira-a-la-uoh-proteger-y-poner-en-valor-el-pukara-de-la-compania\/\">\n                                    <h3 class=\"small-space\">Hist\u00f3rico acuerdo permitir\u00e1 a la UOH proteger y poner en valor el Pukar\u00e1 de La Compa\u00f1\u00eda<\/h3><\/a>\n\n                                    <p>Acuerdo impulsado por el CDE permitir\u00e1 que uno de los sitios arqueol\u00f3gicos m\u00e1s importantes de Chile quede bajo el resguardo de una universidad estatal y se transforme en un espacio permanente para la investigaci\u00f3n cient\u00edfica, la educaci\u00f3n patrimonial y el desarrollo cultural de la Regi\u00f3n de O\u2019Higgins.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/admision\/2026\/08\/28\/historico-acuerdo-permitira-a-la-uoh-proteger-y-poner-en-valor-el-pukara-de-la-compania\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><div class=\"  col-sm-6 col-md-4 img-article\">\n                                        <div class=\"content-news-display row m-0 p-0\"><div class=\"holder p-0 \"><div class=\"img-wrap img-wrap-news\">\n                                        <div class=\"caption__news-category\">\n                                        <a href=\"https:\/\/www.uoh.cl\/admision\/category\/admision\/\">\n                                        Admisi\u00f3n<\/a><\/div><img decoding=\"async\" class=\"w-100 h-100 lazyload\" data-src=\"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2026\/08\/IMG_7106-scaled.jpg\" alt=\"M\u00e1s de 1.600 estudiantes de O\u2019Higgins viven experiencia de exploraci\u00f3n vocacional en un nuevo Puertas Abiertas de Campus Colchagua\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/1707;object-fit: cover; object-position: center;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><\/div><div class=\"caption py-3 caption__news py-md-3 pb-md-5\">\n                                    <span class=\"caption__date\">Viernes 14, Agosto<\/span>\n                                     <a href=\"https:\/\/www.uoh.cl\/admision\/2026\/08\/14\/mas-de-1-600-estudiantes-de-ohiggins-viven-experiencia-de-exploracion-vocacional-en-un-nuevo-puertas-abiertas-de-campus-colchagua\/\">\n                                    <h3 class=\"small-space\">M\u00e1s de 1.600 estudiantes de O\u2019Higgins viven experiencia de exploraci\u00f3n vocacional en un nuevo Puertas Abiertas de Campus Colchagua<\/h3><\/a>\n\n                                    <p>La visita a las instalaciones de la Escuela de Ciencias Agroalimentarias, Animales y Ambientales, ubicadas en San Fernando, const\u00f3 de recorridos guiados por instalaciones y laboratorios, charlas y experiencias de laboratorio.<\/p>\n                                    <a class=\"link link--bold mt-md-3\" href=\"https:\/\/www.uoh.cl\/admision\/2026\/08\/14\/mas-de-1-600-estudiantes-de-ohiggins-viven-experiencia-de-exploracion-vocacional-en-un-nuevo-puertas-abiertas-de-campus-colchagua\/\">Saber m\u00e1s <span class=\"icon icon--inline icon--link\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22px\"height=\"22px\" viewBox=\"0 0 22 22\" style=\"overflow:visible;enable-background:new 0 0 80 64.6;\" xml:space=\"preserve\"><g clip-path=\"url(#acA)\"><path fill-rule=\"evenodd\" d=\"M21.913 11.266a.93.93 0 000-.711c-.022-.056-.063-.097-.091-.144s-.053-.103-.097-.15L12.306.294c-.357-.379-.955-.394-1.334-.038s-.394.955-.038 1.334l7.917 8.374H.927a.95.95 0 00-.908.983.946.946 0 00.908.908h17.924l-8.089 8.552c-.357.379-.341.977.034 1.334s.977.341 1.334-.034l9.594-10.148c.044-.044.063-.1.097-.15.028-.047.069-.088.091-.141z\"\/><\/g><defs><clipPath id=\"acA\"><path fill=\"#fff\" d=\"M0 0h22v22H0z\"\/><\/clipPath><\/defs><\/svg><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pagination justify-content-center my-5\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/posts\/1087\/\/page\/2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/posts\/1087\/\/page\/3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/posts\/1087\/\/page\/139\">139<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/posts\/1087\/\/page\/2\"><div class=\"icon-pagination-next\"> <?xml version=\"1.0\" ?><svg viewBox=\"0 0 96 96\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><title\/><path d=\"M39.3756,48.0022l30.47-25.39a6.0035,6.0035,0,0,0-7.6878-9.223L26.1563,43.3906a6.0092,6.0092,0,0,0,0,9.2231L62.1578,82.615a6.0035,6.0035,0,0,0,7.6878-9.2231Z\"\/><\/svg> <\/div><\/a><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Cuatro nuevas carreras de pregrado se suman a la oferta de la Estatal de O\u2019Higgins el pr\u00f3ximo a\u00f1o. <\/p>\n","protected":false},"author":34,"featured_media":1092,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[39],"tags":[],"class_list":["post-1087","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-admision-uoh"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UOH realiza \u201cPuertas Abiertas\u201d con nueva oferta acad\u00e9mica de cara al Proceso de Admisi\u00f3n 2023 - Admisi\u00f3n UOH<\/title>\n<meta name=\"description\" content=\"Cuatro nuevas carreras de pregrado se suman a la oferta de la Estatal de O\u2019Higgins el pr\u00f3ximo a\u00f1o.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UOH realiza \u201cPuertas Abiertas\u201d con nueva oferta acad\u00e9mica de cara al Proceso de Admisi\u00f3n 2023 - Admisi\u00f3n UOH\" \/>\n<meta property=\"og:description\" content=\"Cuatro nuevas carreras de pregrado se suman a la oferta de la Estatal de O\u2019Higgins el pr\u00f3ximo a\u00f1o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uoh.cl\/admision\/2022\/09\/27\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Admisi\u00f3n UOH\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-27T14:45:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-27T14:58:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2022\/09\/Puertas-Abiertas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Universidad de O&#039;Higgins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Universidad de O&#039;Higgins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/2022\\\/09\\\/27\\\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/2022\\\/09\\\/27\\\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\\\/\"},\"author\":{\"name\":\"Universidad de O'Higgins\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/#\\\/schema\\\/person\\\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"headline\":\"UOH realiza \u201cPuertas Abiertas\u201d con nueva oferta acad\u00e9mica de cara al Proceso de Admisi\u00f3n 2023\",\"datePublished\":\"2022-09-27T14:45:27+00:00\",\"dateModified\":\"2022-09-27T14:58:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/2022\\\/09\\\/27\\\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\\\/\"},\"wordCount\":944,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/2022\\\/09\\\/27\\\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/09\\\/Puertas-Abiertas.jpg\",\"articleSection\":[\"Admisi\u00f3n UOH\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/2022\\\/09\\\/27\\\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/2022\\\/09\\\/27\\\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\\\/\",\"url\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/2022\\\/09\\\/27\\\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\\\/\",\"name\":\"UOH realiza \u201cPuertas Abiertas\u201d con nueva oferta acad\u00e9mica de cara al Proceso de Admisi\u00f3n 2023 - Admisi\u00f3n UOH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/2022\\\/09\\\/27\\\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/2022\\\/09\\\/27\\\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/09\\\/Puertas-Abiertas.jpg\",\"datePublished\":\"2022-09-27T14:45:27+00:00\",\"dateModified\":\"2022-09-27T14:58:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/#\\\/schema\\\/person\\\/ea242e676c7d6d7e46fc8b9e39486c4f\"},\"description\":\"Cuatro nuevas carreras de pregrado se suman a la oferta de la Estatal de O\u2019Higgins el pr\u00f3ximo a\u00f1o.\",\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/2022\\\/09\\\/27\\\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/2022\\\/09\\\/27\\\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/09\\\/Puertas-Abiertas.jpg\",\"contentUrl\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/09\\\/Puertas-Abiertas.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/#website\",\"url\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/\",\"name\":\"Admisi\u00f3n UOH\",\"description\":\"Otro sitio de Sitios de Universidad O&#039;higgins\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uoh.cl\\\/admision\\\/#\\\/schema\\\/person\\\/ea242e676c7d6d7e46fc8b9e39486c4f\",\"name\":\"Universidad de O'Higgins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g\",\"caption\":\"Universidad de O'Higgins\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UOH realiza \u201cPuertas Abiertas\u201d con nueva oferta acad\u00e9mica de cara al Proceso de Admisi\u00f3n 2023 - Admisi\u00f3n UOH","description":"Cuatro nuevas carreras de pregrado se suman a la oferta de la Estatal de O\u2019Higgins el pr\u00f3ximo a\u00f1o.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"UOH realiza \u201cPuertas Abiertas\u201d con nueva oferta acad\u00e9mica de cara al Proceso de Admisi\u00f3n 2023 - Admisi\u00f3n UOH","og_description":"Cuatro nuevas carreras de pregrado se suman a la oferta de la Estatal de O\u2019Higgins el pr\u00f3ximo a\u00f1o.","og_url":"https:\/\/www.uoh.cl\/admision\/2022\/09\/27\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\/","og_site_name":"Admisi\u00f3n UOH","article_published_time":"2022-09-27T14:45:27+00:00","article_modified_time":"2022-09-27T14:58:47+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2022\/09\/Puertas-Abiertas.jpg","type":"image\/jpeg"}],"author":"Universidad de O'Higgins","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Universidad de O'Higgins","Tiempo estimado de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uoh.cl\/admision\/2022\/09\/27\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\/#article","isPartOf":{"@id":"https:\/\/www.uoh.cl\/admision\/2022\/09\/27\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\/"},"author":{"name":"Universidad de O'Higgins","@id":"https:\/\/www.uoh.cl\/admision\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"headline":"UOH realiza \u201cPuertas Abiertas\u201d con nueva oferta acad\u00e9mica de cara al Proceso de Admisi\u00f3n 2023","datePublished":"2022-09-27T14:45:27+00:00","dateModified":"2022-09-27T14:58:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uoh.cl\/admision\/2022\/09\/27\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\/"},"wordCount":944,"commentCount":0,"image":{"@id":"https:\/\/www.uoh.cl\/admision\/2022\/09\/27\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2022\/09\/Puertas-Abiertas.jpg","articleSection":["Admisi\u00f3n UOH"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.uoh.cl\/admision\/2022\/09\/27\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.uoh.cl\/admision\/2022\/09\/27\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\/","url":"https:\/\/www.uoh.cl\/admision\/2022\/09\/27\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\/","name":"UOH realiza \u201cPuertas Abiertas\u201d con nueva oferta acad\u00e9mica de cara al Proceso de Admisi\u00f3n 2023 - Admisi\u00f3n UOH","isPartOf":{"@id":"https:\/\/www.uoh.cl\/admision\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uoh.cl\/admision\/2022\/09\/27\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.uoh.cl\/admision\/2022\/09\/27\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2022\/09\/Puertas-Abiertas.jpg","datePublished":"2022-09-27T14:45:27+00:00","dateModified":"2022-09-27T14:58:47+00:00","author":{"@id":"https:\/\/www.uoh.cl\/admision\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f"},"description":"Cuatro nuevas carreras de pregrado se suman a la oferta de la Estatal de O\u2019Higgins el pr\u00f3ximo a\u00f1o.","inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uoh.cl\/admision\/2022\/09\/27\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.uoh.cl\/admision\/2022\/09\/27\/uoh-realiza-puertas-abiertas-con-nueva-oferta-academica-de-cara-al-proceso-de-admision-2023\/#primaryimage","url":"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2022\/09\/Puertas-Abiertas.jpg","contentUrl":"https:\/\/www.uoh.cl\/admision\/wp-content\/uploads\/sites\/2\/2022\/09\/Puertas-Abiertas.jpg","width":1500,"height":1000},{"@type":"WebSite","@id":"https:\/\/www.uoh.cl\/admision\/#website","url":"https:\/\/www.uoh.cl\/admision\/","name":"Admisi\u00f3n UOH","description":"Otro sitio de Sitios de Universidad O&#039;higgins","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uoh.cl\/admision\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/www.uoh.cl\/admision\/#\/schema\/person\/ea242e676c7d6d7e46fc8b9e39486c4f","name":"Universidad de O'Higgins","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78fcb76ca05efae11fd355943c01a832a29786cc00d85b1a82c301bea2b2a214?s=96&d=mm&r=g","caption":"Universidad de O'Higgins"}}]}},"_links":{"self":[{"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/posts\/1087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/comments?post=1087"}],"version-history":[{"count":2,"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/posts\/1087\/revisions"}],"predecessor-version":[{"id":1091,"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/posts\/1087\/revisions\/1091"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/media\/1092"}],"wp:attachment":[{"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/media?parent=1087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/categories?post=1087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uoh.cl\/admision\/wp-json\/wp\/v2\/tags?post=1087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}